{"id":4597,"date":"2026-04-21T14:26:09","date_gmt":"2026-04-21T12:26:09","guid":{"rendered":"https:\/\/arthroseactive.be\/onze-aanpak-2\/"},"modified":"2026-05-13T11:17:14","modified_gmt":"2026-05-13T09:17:14","slug":"onze-aanpak","status":"publish","type":"page","link":"https:\/\/arthroseactive.be\/nl\/onze-aanpak\/","title":{"rendered":"Onze aanpak"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4597\" class=\"elementor elementor-4597 elementor-4346\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3847b78 e-con-full e-flex e-con e-parent\" data-id=\"3847b78\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4f2babc elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"4f2babc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Onze aanpak<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9749bc2 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"9749bc2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Artrose Active is onze manier om te zeggen: artrose is geen eindpunt, maar een uitdaging die we beter kunnen begrijpen, anticiperen en behandelen, zodat u het vertrouwen in uw bewegingsvermogen terugvindt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fba8034 e-con-full e-flex e-con e-child\" data-id=\"fba8034\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fe00dc9 elementor-widget elementor-widget-image\" data-id=\"fe00dc9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"443\" height=\"430\" src=\"https:\/\/arthroseactive.be\/wp-content\/uploads\/2025\/12\/Group-395ddd.png\" class=\"attachment-full size-full wp-image-4009\" alt=\"\" srcset=\"https:\/\/arthroseactive.be\/wp-content\/uploads\/2025\/12\/Group-395ddd.png 443w, https:\/\/arthroseactive.be\/wp-content\/uploads\/2025\/12\/Group-395ddd-300x291.png 300w\" sizes=\"(max-width: 443px) 100vw, 443px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0773e42 elementor-widget elementor-widget-image\" data-id=\"0773e42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"488\" height=\"481\" src=\"https:\/\/arthroseactive.be\/wp-content\/uploads\/2025\/12\/Group-395f25.png\" class=\"attachment-full size-full wp-image-4010\" alt=\"\" srcset=\"https:\/\/arthroseactive.be\/wp-content\/uploads\/2025\/12\/Group-395f25.png 488w, https:\/\/arthroseactive.be\/wp-content\/uploads\/2025\/12\/Group-395f25-300x296.png 300w\" sizes=\"(max-width: 488px) 100vw, 488px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a2ff06 elementor-widget elementor-widget-image\" data-id=\"1a2ff06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"461\" height=\"429\" src=\"https:\/\/arthroseactive.be\/wp-content\/uploads\/2025\/12\/Group-39557.png\" class=\"attachment-full size-full wp-image-4011\" alt=\"\" srcset=\"https:\/\/arthroseactive.be\/wp-content\/uploads\/2025\/12\/Group-39557.png 461w, https:\/\/arthroseactive.be\/wp-content\/uploads\/2025\/12\/Group-39557-300x279.png 300w\" sizes=\"(max-width: 461px) 100vw, 461px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c2cc30 elementor-widget__width-initial elementor-absolute elementor-widget elementor-widget-image\" data-id=\"7c2cc30\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"311\" height=\"167\" src=\"https:\/\/arthroseactive.be\/wp-content\/uploads\/2026\/05\/Capture-decran-2026-05-13-110646.png\" class=\"attachment-full size-full wp-image-6026\" alt=\"\" srcset=\"https:\/\/arthroseactive.be\/wp-content\/uploads\/2026\/05\/Capture-decran-2026-05-13-110646.png 311w, https:\/\/arthroseactive.be\/wp-content\/uploads\/2026\/05\/Capture-decran-2026-05-13-110646-300x161.png 300w\" sizes=\"(max-width: 311px) 100vw, 311px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8127a56 elementor-absolute e-transform elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"8127a56\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_transform_rotateZ_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_laptop&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"187\" height=\"183\" viewBox=\"0 0 187 183\" fill=\"none\"><path d=\"M37.4278 32.7312L37.4905 32.7439C37.5114 32.7481 37.5449 32.7439 37.591 32.7314C37.6119 32.7356 37.6411 32.7524 37.6788 32.7817C37.7958 32.8488 37.9025 32.8594 37.9988 32.8135C38.0448 32.801 38.0888 32.799 38.1306 32.8074C38.1724 32.8158 38.2038 32.8222 38.2247 32.8264C38.2581 32.8766 38.2999 32.885 38.3502 32.8516C38.3711 32.8558 38.3836 32.8475 38.3879 32.8266C38.3921 32.8057 38.4067 32.7869 38.4319 32.7702L38.3754 32.7262C38.2751 32.6842 38.1203 32.6422 37.9112 32.6C37.8485 32.5874 37.8233 32.6041 37.8358 32.6502C37.8567 32.6544 37.8672 32.6565 37.8672 32.6565C37.8421 32.6732 37.8295 32.6815 37.8295 32.6815C37.7793 32.7149 37.7061 32.7002 37.6099 32.6373C37.4928 32.5702 37.4134 32.5325 37.3716 32.5241L37.0078 32.3855L36.989 32.3165C36.989 32.3165 36.9911 32.306 36.9953 32.2851C36.9953 32.2851 37.0058 32.2872 37.0267 32.2914L37.0581 32.2977C37.0873 32.3689 37.127 32.3878 37.1772 32.3544C37.2024 32.3377 37.2254 32.3314 37.2463 32.3356C37.2421 32.3565 37.2504 32.3691 37.2714 32.3733L37.4533 32.4426C37.378 32.3839 37.33 32.3525 37.309 32.3483L36.6882 32.0274L36.6317 31.9834C36.6317 31.9834 36.6338 31.9729 36.638 31.952C36.638 31.952 36.6276 31.9499 36.6067 31.9457C36.6276 31.9499 36.6401 31.9416 36.6444 31.9207L36.889 32.0026L36.9831 32.0215C36.9831 32.0215 36.9936 32.0236 37.0145 32.0278C37.0145 32.0278 37.0166 32.0174 37.0208 31.9964C36.9999 31.9922 36.9915 31.9797 36.9958 31.9588L36.9393 31.9148L37.0021 31.9274C37.0899 31.9233 37.1966 31.9339 37.3221 31.9592C37.3848 31.9718 37.4246 31.9363 37.4415 31.8526L37.4101 31.8463C37.4352 31.8296 37.452 31.8004 37.4604 31.7585C37.4437 31.7334 37.4249 31.7187 37.404 31.7145L37.4103 31.6832L37.4417 31.6895C37.5462 31.7105 37.6278 31.7378 37.6863 31.7714C37.9498 31.8679 38.1568 31.9205 38.3074 31.929L38.4643 31.9606C38.5145 31.9272 38.5396 31.9105 38.5396 31.9105L38.5083 31.9042C38.4497 31.8707 38.3619 31.8203 38.2449 31.7532C38.1236 31.7071 38.0358 31.6568 37.9815 31.6023C37.923 31.5688 37.8394 31.4975 37.7307 31.3886C37.7307 31.3886 37.7328 31.3781 37.7371 31.3572C37.7371 31.3572 37.7475 31.3593 37.7684 31.3635C37.8479 31.4013 37.9712 31.437 38.1386 31.4707L38.6592 31.6408L38.7847 31.6661C38.8223 31.6954 38.8934 31.7206 38.998 31.7417C39.0147 31.7668 39.0356 31.771 39.0607 31.7543C39.0607 31.7543 39.0712 31.7564 39.0921 31.7606L39.1612 31.7419L39.3494 31.7798C39.5376 31.8177 39.6861 31.8367 39.7949 31.8368C39.9622 31.8705 40.1965 31.8959 40.4977 31.913C40.8407 31.9385 41.0687 31.9409 41.1817 31.9202L41.7967 31.946L42.2925 31.9153C42.8155 31.9118 43.1 31.9038 43.146 31.8913C43.2548 31.8914 43.5122 31.8562 43.9181 31.7856C43.9808 31.7982 44.0352 31.7983 44.0813 31.7858L44.1503 31.767L44.1566 31.7357L44.1253 31.7293C44.0332 31.7543 43.9662 31.7626 43.9244 31.7542L43.8617 31.7416L43.8994 31.7165L44.207 31.6479C44.2279 31.6521 44.2404 31.6437 44.2446 31.6228L44.2133 31.6165C44.1505 31.6039 44.0961 31.6038 44.0501 31.6163L43.9937 31.5723L44.0564 31.5849C44.2657 31.5182 44.4665 31.4934 44.659 31.5104C44.7259 31.5021 44.7782 31.5126 44.8158 31.542C44.8492 31.5922 44.8911 31.6006 44.9413 31.5672C44.9916 31.5338 45.0167 31.5171 45.0167 31.5171L45.3997 31.3984C45.5293 31.4027 45.6758 31.3778 45.8391 31.3236C45.8391 31.3236 45.8412 31.3131 45.8454 31.2922C45.8454 31.2922 45.8558 31.2943 45.8767 31.2985C45.8349 31.2901 45.814 31.2859 45.814 31.2859C45.768 31.2984 45.7261 31.29 45.6885 31.2607C45.6676 31.2564 45.6509 31.2313 45.6384 31.1853L45.5757 31.1727L45.0923 31.3038C45.0504 31.2954 44.8475 31.3307 44.4834 31.4097C44.3871 31.4556 44.2971 31.4702 44.2135 31.4533L43.705 31.5468C43.705 31.5468 43.6799 31.5635 43.6297 31.5969L43.4915 31.6344C43.4915 31.6344 43.4811 31.6323 43.4602 31.6281C43.4393 31.6239 43.4371 31.6343 43.4539 31.6595L43.4162 31.6845L43.1526 31.6967C42.8598 31.6378 42.5774 31.6353 42.3054 31.6894C42.2342 31.7186 42.1672 31.7269 42.1045 31.7142C42.0418 31.7016 41.9978 31.7036 41.9727 31.7203L41.3577 31.6944L40.8682 31.6938C40.7761 31.7188 40.7092 31.7271 40.6674 31.7187C40.4498 31.7184 40.3096 31.7119 40.2469 31.6993C39.9541 31.6404 39.7429 31.6087 39.6132 31.6044L39.1677 31.5473C39.038 31.543 38.879 31.5219 38.6908 31.484C38.6532 31.4546 38.5821 31.4294 38.4775 31.4084C38.4566 31.4042 38.444 31.4125 38.4398 31.4334L38.4649 31.4711C38.5276 31.4838 38.5778 31.5047 38.6154 31.5341L38.6468 31.5404L38.6154 31.5341L38.4586 31.5025L38.3645 31.4835L38.2076 31.452L38.1762 31.4457L38.2139 31.4206L38.3457 31.4145L38.352 31.3831L38.3207 31.3768L38.2266 31.3579L37.8564 31.2507L37.6055 31.2002L37.5177 31.1499L37.4612 31.1059L37.524 31.1185C37.57 31.106 37.6349 31.1082 37.7185 31.125C37.8022 31.1419 37.8775 31.1461 37.9444 31.1378L37.9758 31.1442L37.9507 31.1065L37.888 31.0938C37.8504 31.0645 37.7542 31.0016 37.5996 30.9052L37.5682 30.8989L37.6309 30.9115L38.1642 31.0189L38.227 31.0315L38.1642 31.0189C37.9886 30.9183 37.8109 30.8281 37.6311 30.7484C37.5475 30.7315 37.4868 30.7084 37.4492 30.6791L37.3928 30.6351L37.4619 30.6163L37.9387 30.6797C37.9554 30.7048 37.9868 30.7112 38.0328 30.6987C38.0789 30.6862 38.1228 30.6841 38.1646 30.6926L38.196 30.6989L38.171 30.6612C38.0748 30.5983 37.9661 30.5438 37.8448 30.4976C37.7026 30.4472 37.6106 30.4178 37.5688 30.4094L37.5061 30.3968L37.5688 30.4094L37.8511 30.4662L37.9766 30.4915C38.0185 30.4999 38.0519 30.4958 38.0771 30.4791C38.0561 30.4749 38.0499 30.4518 38.0583 30.41L38.0646 30.3786C38.1901 30.4039 38.2717 30.4312 38.3093 30.4605L38.3407 30.4668L38.1838 30.4353L38.1461 30.4603L38.1775 30.4666C38.2402 30.4793 38.2799 30.4982 38.2967 30.5233C38.4012 30.5443 38.5329 30.5926 38.6918 30.6681L38.7232 30.6744C38.7692 30.6619 38.8655 30.6704 39.0119 30.6999C39.0537 30.7083 39.0662 30.7 39.0495 30.6748L39.0872 30.6498L39.6456 30.7948C39.6874 30.8033 39.7418 30.8033 39.8088 30.7951C39.8506 30.8035 39.9112 30.8266 39.9907 30.8643C40.0492 30.8979 40.1517 30.9294 40.2981 30.9588C40.4068 30.959 40.5135 30.9696 40.6181 30.9906C40.7184 31.0326 40.823 31.0536 40.9318 31.0538C41.0154 31.0706 41.1891 31.0729 41.4527 31.0607C41.5029 31.0273 41.5615 31.0065 41.6285 30.9982C41.6745 30.9857 41.7205 30.9732 41.7666 30.9607C41.8084 30.9691 41.8628 30.9692 41.9297 30.9609C42.0134 30.9778 42.0845 31.003 42.143 31.0365L42.2371 31.0554L42.2685 31.0618L42.1931 31.1119L42.1367 31.0679L42.1053 31.0616L42.0613 31.118L42.1241 31.1306C42.1199 31.1515 42.1282 31.1641 42.1491 31.1683C42.1282 31.1641 42.1178 31.162 42.1178 31.162C42.1135 31.1829 42.1114 31.1933 42.1114 31.1933C42.1114 31.1933 42.101 31.1912 42.0801 31.187L42.0173 31.1744C41.9546 31.1618 41.8353 31.1595 41.6596 31.1677L41.5906 31.1864L41.5278 31.1738C41.4777 31.0984 41.415 31.0858 41.3396 31.1359L41.0196 31.1041L40.9505 31.1228C40.9505 31.1228 40.961 31.1249 40.9819 31.1292C40.9819 31.1292 40.9798 31.1396 40.9756 31.1605L41.0069 31.1668L40.9756 31.1605L40.712 31.1727C40.5865 31.1475 40.5007 31.1411 40.4547 31.1536L40.417 31.1786L40.4484 31.185C40.4902 31.1934 40.509 31.208 40.5048 31.229L40.4358 31.2477C40.2266 31.2056 40.0677 31.1845 39.9589 31.1843C39.7707 31.1464 39.6305 31.14 39.5384 31.165C39.4296 31.1648 39.3334 31.1563 39.2498 31.1395C39.141 31.1394 39.0322 31.1392 38.9234 31.1391L38.8921 31.1328C38.8796 31.0867 38.842 31.0574 38.7792 31.0448C38.6914 31.0488 38.637 31.0488 38.6161 31.0446L38.5533 31.0319L38.5784 31.0696L38.6348 31.1136L39.074 31.202C39.1158 31.2105 39.1472 31.2168 39.1681 31.221C39.1848 31.2461 39.1931 31.2587 39.1931 31.2587C39.1638 31.2963 39.1701 31.3193 39.2119 31.3277C39.2119 31.3277 39.2433 31.334 39.306 31.3467C39.3645 31.3802 39.4189 31.3803 39.4692 31.3469L39.5005 31.3532C39.5172 31.3783 39.5486 31.3846 39.5946 31.3721C39.6156 31.3764 39.6365 31.3806 39.6574 31.3848C39.6741 31.4099 39.718 31.4079 39.7892 31.3787C39.8143 31.362 39.8478 31.3578 39.8896 31.3662C39.9105 31.3705 39.9335 31.3642 39.9587 31.3475L39.9524 31.3789C39.9314 31.3747 39.9189 31.383 39.9147 31.4039C39.9147 31.4039 39.9251 31.406 39.946 31.4102C39.9418 31.4312 39.9523 31.4333 39.9774 31.4166L40.1029 31.4418L40.1092 31.4105L40.1406 31.4168L40.1719 31.4231C40.3393 31.4568 40.4773 31.4737 40.5861 31.4738C40.607 31.478 40.6196 31.4697 40.6238 31.4488C40.628 31.4278 40.6405 31.4195 40.6615 31.4237C40.6615 31.4237 40.6719 31.4258 40.6928 31.43C40.6928 31.43 40.6907 31.4405 40.6865 31.4614L40.7116 31.4991L40.7179 31.4677L40.8623 31.3989C40.8623 31.3989 40.879 31.424 40.9124 31.4742L40.9752 31.4869C41.0379 31.4995 41.1362 31.4975 41.2701 31.481C41.2534 31.4558 41.2576 31.4349 41.2828 31.4182L41.3769 31.4372C41.3978 31.4414 41.4292 31.4477 41.471 31.4561C41.4877 31.4812 41.5191 31.4876 41.5651 31.4751C41.6278 31.4877 41.7471 31.4899 41.9228 31.4818C42.0107 31.4777 42.2889 31.4467 42.7576 31.3887L43.2848 31.3643L43.4606 31.3018C43.5442 31.3186 43.6321 31.3145 43.7242 31.2895C43.7451 31.2937 43.7577 31.2854 43.7619 31.2645L43.7305 31.2582C43.7305 31.2582 43.72 31.2561 43.6991 31.2518C43.6782 31.2476 43.6552 31.2539 43.6301 31.2706C43.6092 31.2664 43.6008 31.2538 43.605 31.2329L43.58 31.1952C43.513 31.2035 43.4461 31.2118 43.3791 31.2201C43.3331 31.2326 43.287 31.245 43.241 31.2575L42.9587 31.2007C42.8959 31.1881 42.8582 31.2131 42.8456 31.2759L42.8142 31.2696C42.7933 31.2653 42.7619 31.259 42.7201 31.2506C42.6741 31.2631 42.6427 31.2568 42.626 31.2317C42.6093 31.2065 42.5905 31.1919 42.5696 31.1877C42.5444 31.2044 42.5214 31.2106 42.5005 31.2064L42.4315 31.2251L42.5068 31.175C42.6407 31.1585 42.76 31.1607 42.8645 31.1818L42.9399 31.1316L42.9462 31.1003C42.9631 31.0166 42.9506 30.9706 42.9087 30.9622L42.8774 30.9558L42.9151 30.9308L42.9464 30.9371L42.9904 30.8807L42.9591 30.8744C42.8879 30.9036 42.8105 30.9097 42.7268 30.8929C42.639 30.897 42.5741 30.8948 42.5323 30.8864L42.5009 30.8801L42.4068 30.8611L42.5072 30.8487C42.6287 30.7861 42.7542 30.757 42.8839 30.7613C42.8881 30.7404 42.9111 30.7341 42.953 30.7426C42.9948 30.751 43.0073 30.7426 42.9906 30.7175L42.9656 30.6798L42.997 30.6861L43.3987 30.6364L43.2606 30.6739L43.2292 30.6676L43.2542 30.7053L43.5555 30.668L43.5869 30.6743L43.5555 30.668L43.3987 30.6364L43.7126 30.5364L43.744 30.5427L43.7126 30.5364L43.1226 30.5482L43.0913 30.5419L43.129 30.5169C43.1541 30.5002 43.1771 30.4939 43.198 30.4981C43.2398 30.5065 43.2733 30.5024 43.2984 30.4857C43.3194 30.4899 43.3319 30.4816 43.3361 30.4606L43.3048 30.4543L43.2734 30.448L43.3048 30.4543L43.3488 30.3979L43.286 30.3853L43.2547 30.379L43.2923 30.3539L43.4555 30.3541C43.5476 30.3291 43.6501 30.3062 43.7631 30.2855C43.8928 30.2898 44.0162 30.2711 44.1334 30.2295L44.5855 30.092L44.7236 30.0545C44.7445 30.0587 44.7571 30.0503 44.7613 30.0294L44.7299 30.0231L44.6985 30.0168L44.1901 30.1103L43.8448 30.204L42.9096 30.3095C42.7338 30.3176 42.5832 30.3091 42.4578 30.2838C42.2109 30.3212 41.9703 30.3271 41.736 30.3017L40.9452 30.3384C40.7486 30.3423 40.4997 30.3357 40.1985 30.3186L39.7466 30.2929L39.1756 30.2106C39.1087 30.2189 39.0125 30.2104 38.887 30.1851L38.8933 30.1538L39.0815 30.1917C39.2991 30.1919 39.6421 30.2175 40.1107 30.2683L40.9265 30.2693C41.1441 30.2696 41.5373 30.2617 42.1064 30.2457L42.5268 30.2651C42.5938 30.2568 42.6607 30.2485 42.7277 30.2402C42.7946 30.2319 42.872 30.2258 42.9599 30.2217L43.462 30.1596L44.209 30.0162L44.9183 29.8978C45.0104 29.8729 45.2301 29.8083 45.5775 29.7041C45.9291 29.5791 46.2515 29.4372 46.5445 29.2786L46.7203 29.2161C46.9213 29.0825 47.0218 29.0156 47.0218 29.0156C47.0721 28.9822 47.0993 28.9551 47.1035 28.9342C47.1328 28.8965 47.1601 28.8694 47.1852 28.8527C47.2564 28.8235 47.3296 28.7838 47.405 28.7337C47.5055 28.6669 47.5934 28.6084 47.6688 28.5583C47.8865 28.4498 48.054 28.3203 48.1714 28.1699C48.2216 28.1365 48.2488 28.1093 48.253 28.0884C48.3913 27.9421 48.4836 27.754 48.5299 27.5239L48.6619 27.3547C48.6956 27.1873 48.6895 27.0556 48.6436 26.9593C48.6227 26.9551 48.6164 26.932 48.6248 26.8902C48.6415 26.9153 48.6499 26.9279 48.6499 26.9279C48.6833 26.9781 48.7189 26.9635 48.7566 26.8841C48.7775 26.8883 48.7901 26.88 48.7943 26.859C48.8027 26.8172 48.8069 26.7963 48.8069 26.7963C48.7902 26.7712 48.784 26.7482 48.7882 26.7272C48.7966 26.6854 48.8029 26.654 48.8072 26.6331L48.732 26.5201C48.6652 26.4196 48.5231 26.2604 48.3058 26.0426C48.2724 25.9923 48.1512 25.8918 47.9422 25.7409L47.2213 25.1061C47.0542 24.9637 46.9079 24.8254 46.7826 24.6914L46.7512 24.685C46.7512 24.685 46.7491 24.6955 46.7449 24.7164C46.7449 24.7164 46.7553 24.7185 46.7762 24.7227C46.8598 24.8484 46.9579 24.9552 47.0708 25.0432L47.1146 25.1499L47.0205 25.131L46.9641 25.087L46.9327 25.0806L46.9201 25.1434C47.1205 25.4449 47.2834 25.6626 47.4087 25.7967L47.553 25.891C47.5194 25.9495 47.5298 26.006 47.5841 26.0605L47.9164 26.3559L47.9351 26.4249L47.8787 26.3809C47.7658 26.2929 47.653 26.2049 47.5401 26.1169C47.4273 26.0289 47.3228 25.9535 47.2266 25.8906C47.1932 25.8403 47.1013 25.7565 46.9508 25.6392L46.7438 25.5323L46.7062 25.5573L46.7249 25.6264L46.9317 25.8965L46.9504 25.9655C47.0089 25.9991 47.105 26.1164 47.2386 26.3174C47.2553 26.3425 47.2846 26.3593 47.3264 26.3677C47.3431 26.3928 47.3933 26.4138 47.477 26.4306L47.5397 26.4433L47.6024 26.4559C47.6861 26.4727 47.7822 26.5356 47.8909 26.6445C47.8825 26.6863 47.8992 26.7115 47.941 26.7199C47.9368 26.7408 47.9451 26.7534 47.966 26.7576C47.987 26.7618 47.9744 26.7701 47.9284 26.7826L47.9471 26.8517C47.9471 26.8517 47.9805 26.9019 48.0473 27.0024L48.041 27.0338L48.0096 27.0275L47.7902 26.8201C47.7693 26.8159 47.7589 26.8138 47.7589 26.8138C47.7631 26.7929 47.7652 26.7824 47.7652 26.7824L47.3388 26.4681L47.3138 26.4304C47.1716 26.38 47.0566 26.3025 46.9689 26.1978C46.9355 26.1475 46.8895 26.1056 46.831 26.0721C46.7934 26.0427 46.7558 26.0134 46.7182 25.9841C46.6763 25.9757 46.6596 25.9505 46.6681 25.9087C46.6389 25.8375 46.5657 25.7684 46.4487 25.7013C46.3358 25.6133 46.2648 25.5337 46.2356 25.4626C46.2398 25.4417 46.1938 25.3998 46.0977 25.3369C45.9556 25.1777 45.8742 25.0416 45.8535 24.9287C45.8368 24.9035 45.8347 24.8596 45.8473 24.7969L45.7785 24.6524L45.7848 24.6211C45.5717 24.3823 45.4652 24.2629 45.4652 24.2629L45.2334 23.9551L44.9329 23.3397C44.8411 23.1472 44.7849 22.9944 44.7641 22.8814C44.7432 22.8772 44.7327 22.8751 44.7327 22.8751C44.7369 22.8542 44.739 22.8437 44.739 22.8437C44.6847 22.7892 44.6555 22.7181 44.6514 22.6302C44.6474 22.5424 44.6474 22.488 44.6516 22.467C44.6309 22.3541 44.608 22.2515 44.583 22.1595C44.558 22.0674 44.5414 21.9879 44.5331 21.9209L44.5274 21.4628L44.5215 21.1678L44.5718 21.08L44.5531 21.011C44.5615 20.9691 44.5762 20.9503 44.5971 20.9545C44.6222 20.9378 44.6264 20.9169 44.6097 20.8918C44.6139 20.8709 44.6056 20.8583 44.5847 20.8541C44.5847 20.8541 44.5889 20.8332 44.5973 20.7914L44.6415 20.5718L44.711 20.2267C44.7447 20.0594 44.8348 19.8817 44.9815 19.6936C45.0318 19.6602 45.0673 19.6456 45.0883 19.6498C45.1468 19.6833 45.1928 19.6709 45.2264 19.6123L45.5847 19.1296L45.6287 19.0731C45.6245 19.094 45.6328 19.1066 45.6538 19.1108L45.6474 19.1422C45.6893 19.1506 45.7248 19.136 45.7542 19.0984C45.8086 19.0441 45.8275 19.0043 45.8108 18.9792C45.7941 18.9541 45.7983 18.9332 45.8234 18.9165C45.8904 18.9082 45.9364 18.8957 45.9616 18.879C46.0076 18.8665 46.0432 18.8519 46.0683 18.8352L46.1374 18.8165C46.2043 18.8082 46.2462 18.7622 46.263 18.6786C46.2463 18.6534 46.2401 18.6304 46.2443 18.6095C46.2736 18.5719 46.2883 18.5531 46.2883 18.5531L46.3574 18.5343L46.3447 18.5971L46.3384 18.6285L46.3698 18.6348C46.5121 18.5764 46.6377 18.4929 46.7467 18.3842C46.8765 18.2798 46.9686 18.2004 47.0231 18.1461L47.0608 18.121L47.1361 18.0709L47.0858 18.1587C47.0732 18.2215 47.0543 18.2612 47.0292 18.2779L47.0919 18.2905C47.1422 18.2571 47.1694 18.23 47.1736 18.209L47.5379 18.0212C47.7388 17.8876 47.8393 17.8208 47.8393 17.8208C47.8854 17.8083 48.0424 17.7311 48.3103 17.5892L48.9697 17.2323C49.066 17.1864 49.1602 17.151 49.2523 17.126C49.3653 17.1052 49.4699 17.0719 49.5662 17.026L49.7546 16.9007C49.9472 16.8089 50.1355 16.738 50.3197 16.688C50.5038 16.6381 50.6231 16.5859 50.6776 16.5316C50.8115 16.515 50.9161 16.4817 50.9915 16.4316L51.2427 16.3189L51.5189 16.244L51.5566 16.2189L51.4939 16.2063L51.2553 16.2562L51.224 16.2499L51.2553 16.2562C51.5358 16.1603 51.7409 16.0602 51.8707 15.9558L51.9398 15.937C52.0109 15.9078 52.0402 15.9246 52.0276 15.9873C52.0025 16.004 51.9982 16.0249 52.0149 16.0501C52.0359 16.0543 52.0484 16.0459 52.0526 16.025C52.195 15.9666 52.3038 15.9124 52.3792 15.8623C52.3792 15.8623 52.4043 15.8456 52.4546 15.8122L52.4859 15.8185C52.5195 15.7599 52.5718 15.7161 52.643 15.6869C52.7141 15.6577 52.7644 15.6243 52.7937 15.5867L52.9318 15.5492C52.9361 15.5283 52.9382 15.5178 52.9382 15.5178C52.9591 15.522 52.9695 15.5241 52.9695 15.5241C53.0238 15.5786 53.0866 15.5912 53.1578 15.562C53.1787 15.5662 53.1996 15.5704 53.2205 15.5746C53.2623 15.5831 53.2916 15.5998 53.3083 15.625C53.3041 15.6459 53.3124 15.6584 53.3333 15.6627C53.3752 15.6711 53.4086 15.6669 53.4338 15.6502C53.4798 15.6377 53.5258 15.6252 53.5719 15.6127C53.643 15.5836 53.7016 15.5627 53.7477 15.5502C53.9151 15.4751 54.0093 15.4397 54.0302 15.4439L54.6204 15.2689C54.7124 15.2439 54.8024 15.2294 54.8903 15.2253C54.9824 15.2003 55.087 15.167 55.2042 15.1253L55.2732 15.1066L55.7 15.0946C55.8046 15.1156 55.9008 15.1241 55.9887 15.12C56.0765 15.116 56.1539 15.1098 56.2209 15.1015L56.4468 15.1143C56.4928 15.1019 56.5577 15.104 56.6413 15.1209L56.8609 15.1651C56.9028 15.1735 56.955 15.184 57.0178 15.1967C57.0847 15.1884 57.137 15.1989 57.1746 15.2282C57.2792 15.2493 57.4737 15.3102 57.758 15.411L58.1094 15.4491C58.2558 15.4785 58.3855 15.5373 58.4983 15.6253C58.515 15.6504 58.5338 15.6651 58.5547 15.6693C58.5966 15.6777 58.6258 15.6945 58.6425 15.7196L58.7617 15.7762C58.7867 15.8683 58.8263 15.9416 58.8807 15.996C58.9392 16.0296 58.9768 16.0589 58.9935 16.084C59.0269 16.1343 59.0436 16.1594 59.0436 16.1594C59.0603 16.1845 59.077 16.2097 59.0937 16.2348C59.1104 16.2599 59.1397 16.2767 59.1815 16.2851C59.2401 16.3186 59.263 16.3668 59.2504 16.4295L59.2441 16.4609C59.2272 16.5446 59.2878 16.622 59.4258 16.6933L59.5199 16.7123C59.5617 16.7207 59.57 16.7333 59.5449 16.75C59.4947 16.7834 59.4925 16.8482 59.5384 16.9445C59.5384 16.9445 59.5551 16.9696 59.5885 17.0199L59.5696 17.114L59.5506 17.2081C59.538 17.2708 59.5421 17.3043 59.563 17.3085C59.6007 17.3379 59.5922 17.3797 59.5378 17.434L59.5188 17.5281L59.5249 17.6599L59.4807 17.8795L59.4241 17.9987C59.3487 18.0488 59.3131 18.1178 59.3171 18.2056C59.3548 18.235 59.3485 18.2664 59.2982 18.2998C59.2731 18.3165 59.2563 18.3457 59.2479 18.3876C59.2395 18.4294 59.2227 18.4586 59.1976 18.4754L59.0969 18.6509L59.0089 18.7638C58.9629 18.7763 58.9126 18.8097 58.8582 18.864C58.8246 18.9225 58.7932 18.9706 58.7639 19.0082C58.7345 19.0459 58.6382 19.1461 58.4748 19.3091L58.0666 19.5533L57.3442 20.0608L56.3581 20.7436C56.2282 20.848 56.044 20.9523 55.8054 21.0566C55.5039 21.2571 55.2255 21.3969 54.9702 21.476C54.853 21.5177 54.7107 21.5761 54.5432 21.6512C54.4009 21.7096 54.2439 21.7868 54.0722 21.8828L53.9529 21.9894L53.6703 22.0957L53.5886 22.1772C53.5217 22.1855 53.5154 22.2168 53.5697 22.2713C53.5906 22.2755 53.599 22.2881 53.5948 22.309L53.419 22.3715L53.1928 22.5218L53.1551 22.5469L52.8103 22.3143C52.689 22.2681 52.6095 22.2847 52.5717 22.3642C52.446 22.5564 52.2681 22.6294 52.038 22.5831C51.9795 22.5496 51.8666 22.516 51.6993 22.4823L51.511 22.4444C51.4483 22.4318 51.4086 22.4129 51.3919 22.3878C51.2957 22.3249 51.2394 22.2265 51.2228 22.0926C51.1853 21.9545 51.1582 21.8729 51.1415 21.8477C51.0914 21.7724 51.0769 21.6824 51.0979 21.5778C51.1106 21.5151 51.1044 21.4377 51.0794 21.3456C51.0252 21.1824 51.0275 21.0087 51.0863 20.8247L51.1872 20.486C51.2836 20.3313 51.4114 20.1829 51.5706 20.0409C51.7172 19.8528 51.9182 19.7192 52.1736 19.64L52.5188 19.5463C52.6402 19.4837 52.747 19.4399 52.8391 19.4149C52.9563 19.3732 53.0504 19.3378 53.1216 19.3086C53.3769 19.2294 53.603 19.1335 53.7998 19.0208L54.5846 18.6891L55.1059 18.3697L55.2817 18.3072L55.8407 17.9628C55.8616 17.967 55.8742 17.9586 55.8784 17.9377C55.9035 17.921 55.9077 17.9001 55.891 17.875L55.7719 17.8183C55.73 17.8099 55.6966 17.814 55.6714 17.8307C55.6505 17.8265 55.6275 17.8328 55.6024 17.8495C55.5815 17.8453 55.5794 17.8557 55.5961 17.8809C55.5834 17.9436 55.5353 17.9665 55.4516 17.9497C55.4349 17.9246 55.4057 17.9078 55.3638 17.8994C55.3429 17.8952 55.3241 17.8805 55.3074 17.8554C55.2865 17.8512 55.2635 17.8574 55.2384 17.8741C55.2174 17.8699 55.1986 17.8552 55.1819 17.8301L54.931 17.7796C54.7009 17.7333 54.5043 17.7372 54.341 17.7914L53.4686 17.9095C53.4476 17.9053 53.4037 17.9074 53.3368 17.9156C53.2949 17.9072 53.2384 17.9176 53.1673 17.9468C53.0794 17.9509 53.002 17.9571 52.935 17.9653C52.8681 17.9736 52.8011 17.9819 52.7342 17.9902L52.3199 18.1026L52.1881 18.1087L51.9432 18.19L51.328 18.3273L50.7379 18.5023C50.6876 18.5357 50.5955 18.5606 50.4616 18.5772L50.0974 18.765C50.0262 18.7942 49.9446 18.8213 49.8525 18.8463C49.7814 18.8755 49.6977 18.913 49.6014 18.9589L49.1931 19.2032C48.9001 19.3618 48.7075 19.4536 48.6154 19.4786C48.1799 19.8044 47.8867 20.0717 47.7358 20.2807C47.5598 20.5064 47.4444 20.7552 47.3897 21.0271L47.3581 21.184L47.3265 21.3408C47.3223 21.3617 47.316 21.3931 47.3076 21.4349C47.3243 21.4601 47.318 21.4914 47.2886 21.529L47.2823 21.5604C47.278 21.6901 47.3071 21.8157 47.3697 21.9371C47.3613 21.9789 47.3654 22.0124 47.3821 22.0375C47.3403 22.0291 47.3194 22.0249 47.3194 22.0249C47.2524 22.0331 47.2148 22.0038 47.2065 21.9369C47.1983 21.8699 47.1962 21.826 47.2004 21.8051C47.2046 21.7841 47.1963 21.7716 47.1754 21.7674C47.1754 21.7674 47.1587 21.7423 47.1253 21.692C47.1168 21.7338 47.1231 21.7569 47.144 21.7611L47.1564 21.8615C47.1898 21.9117 47.1752 21.9305 47.1124 21.9179C47.1124 21.9179 47.102 21.9158 47.0811 21.9116C47.0811 21.9116 47.079 21.9221 47.0747 21.943C47.0914 21.9681 47.083 22.0099 47.0495 22.0685C47.0411 22.1103 47.0431 22.1542 47.0556 22.2002L47.2811 22.5394C47.2811 22.5394 47.279 22.5499 47.2748 22.5708C47.2957 22.575 47.3187 22.5688 47.3438 22.5521C47.3689 22.5354 47.3899 22.5396 47.4066 22.5647C47.4233 22.5898 47.44 22.6149 47.4567 22.6401L47.7135 22.9856C47.7093 23.0065 47.7072 23.0169 47.7072 23.0169C47.7323 23.0002 47.7428 23.0023 47.7386 23.0232L47.7512 22.9605C47.7345 22.9354 47.7304 22.9019 47.7388 22.8601C47.7514 22.7973 47.7494 22.7534 47.7327 22.7283L47.7767 22.6718C47.7976 22.6761 47.806 22.6886 47.8018 22.7095C47.8309 22.7807 47.8999 22.8707 48.0085 22.9796L48.0399 22.986C48.0525 22.9232 48.0755 22.917 48.1089 22.9672L48.2342 23.1557L48.3094 23.2687L48.3344 23.3064C48.3302 23.3273 48.3344 23.3608 48.3469 23.4068C48.3845 23.4362 48.4137 23.4529 48.4346 23.4571C48.4848 23.5325 48.5098 23.5702 48.5098 23.5702L48.5662 23.6142L48.5161 23.5388L48.5224 23.5075L48.5288 23.4761L48.6039 23.5892C48.6248 23.5934 48.6332 23.6059 48.629 23.6268C48.5996 23.6645 48.6267 23.7461 48.7103 23.8717L49.1427 24.3178L49.1991 24.3618C49.241 24.3702 49.264 24.364 49.2682 24.3431L49.3122 24.2867C49.3749 24.2993 49.3896 24.2805 49.3562 24.2302C49.3646 24.1884 49.3605 24.1549 49.3438 24.1298C49.4065 24.1424 49.4358 24.1592 49.4316 24.1801C49.5109 24.3267 49.6048 24.4544 49.7135 24.5633L49.8263 24.6513C50.0227 24.8649 50.2421 25.0723 50.4845 25.2734L50.5096 25.3111L50.4468 25.2985C50.4301 25.2734 50.3904 25.2545 50.3276 25.2419C50.2524 25.1832 50.01 24.9821 49.6004 24.6385L49.6945 24.6574C49.6988 24.6365 49.6842 24.6009 49.6507 24.5507L49.5943 24.5067L49.5316 24.494L49.5503 24.5631C49.5461 24.584 49.5607 24.6196 49.5941 24.6698L49.5627 24.6635C49.5543 24.7053 49.5606 24.7284 49.5815 24.7326C49.5982 24.7577 49.6128 24.7933 49.6253 24.8393C49.642 24.8644 49.6734 24.8708 49.7194 24.8583L49.7444 24.896C49.736 24.9378 49.7569 24.9964 49.807 25.0718C49.8279 25.076 49.8362 25.0885 49.832 25.1094L49.8007 25.1031C49.7421 25.0696 49.6585 24.9983 49.5499 24.8894C49.0484 24.462 48.7496 24.2169 48.6534 24.154C48.6367 24.1289 48.6074 24.1121 48.5656 24.1037C48.5656 24.1037 48.5823 24.1288 48.6157 24.1791L49.0107 24.4871C49.1528 24.6463 49.3909 24.8683 49.7253 25.1532C49.7253 25.1532 49.8632 25.2789 50.139 25.5303L50.4839 25.7629L50.4902 25.7316C50.5111 25.7358 50.5237 25.7274 50.5279 25.7065L50.5466 25.7756L50.5403 25.8069C50.5612 25.8112 50.5863 25.8488 50.6155 25.92C50.6489 25.9702 50.6886 25.9891 50.7346 25.9766C50.768 26.0269 50.8224 26.0813 50.8976 26.14C50.998 26.182 51.0627 26.2385 51.0919 26.3097L51.2359 26.5672C51.2693 26.6174 51.2839 26.653 51.2797 26.6739C51.3174 26.7033 51.3362 26.7179 51.3362 26.7179L51.3612 26.7556C51.3361 26.7723 51.3214 26.7911 51.3172 26.812C51.313 26.833 51.3214 26.8455 51.3423 26.8497C51.359 26.8749 51.3736 26.9104 51.3861 26.9565C51.4028 26.9816 51.4341 26.9879 51.4802 26.9754C51.4802 26.9754 51.4885 26.988 51.5052 27.0131C51.5219 27.0382 51.5282 27.0613 51.524 27.0822C51.4904 27.1407 51.4904 27.1951 51.5238 27.2453L51.5299 27.3771L51.5486 27.4462L51.58 27.4525L51.6303 27.3647L51.6429 27.302L51.668 27.3397L51.7366 27.6472C51.7324 27.6682 51.7261 27.6995 51.7177 27.7414C51.7135 27.7623 51.6988 27.7811 51.6737 27.7978C51.6528 27.7936 51.6402 27.8019 51.636 27.8228C51.6149 27.9274 51.554 28.1219 51.4533 28.4063L51.4783 28.4439C51.5117 28.4942 51.5284 28.5193 51.5284 28.5193C51.5158 28.5821 51.5199 28.6155 51.5408 28.6197L51.5596 28.6888C51.4757 28.8895 51.4211 28.9982 51.396 29.0149C51.3625 29.0735 51.2954 29.1361 51.1949 29.2029L50.9939 29.391L50.9876 29.4223C51.0252 29.4517 51.0189 29.483 50.9686 29.5164C50.9435 29.5331 50.9288 29.552 50.9246 29.5729L50.956 29.5792C50.9518 29.6001 50.9601 29.6127 50.981 29.6169C51.0062 29.6002 51.0062 29.6002 50.981 29.6169C50.9768 29.6378 50.9622 29.6566 50.937 29.6733C50.9119 29.69 50.8889 29.6962 50.868 29.692C50.868 29.692 50.8303 29.7171 50.7549 29.7672C50.7925 29.7965 50.7862 29.8279 50.736 29.8613L50.6793 29.9805C50.6584 29.9763 50.6459 29.9846 50.6417 30.0055C50.608 30.1728 50.4822 30.3651 50.2644 30.5824C50.1052 30.7245 49.7305 30.9646 49.1401 31.3027C48.9475 31.3945 48.7236 31.48 48.4683 31.5591C48.3469 31.6217 48.169 31.6947 47.9346 31.7781L47.4762 31.947C47.3088 32.0221 47.2146 32.0575 47.1937 32.0533C47.1016 32.0783 46.8379 32.1449 46.4027 32.2531L45.5426 32.4717L44.6702 32.5898L44.3939 32.6648L43.6156 32.8018C43.3478 32.835 43.1407 32.8368 42.9943 32.8073L42.0904 32.9191C42.0695 32.9149 42.0339 32.9295 41.9837 32.9629C41.9418 32.9545 41.9084 32.9587 41.8832 32.9754L41.4251 32.9811L41.1992 32.9682C40.7138 33.0011 40.3101 33.0068 39.988 32.9855L39.442 32.9409L39.3793 32.9283L39.4357 32.9723L39.6239 33.0101L39.6867 33.0228L39.649 33.0478C39.6406 33.0897 39.6364 33.1106 39.6364 33.1106L39.6677 33.1169C39.8141 33.1464 39.9752 33.157 40.1509 33.1489L40.3078 33.1805L40.6905 33.2249L40.7847 33.2438C40.7637 33.2396 40.7512 33.248 40.747 33.2689C40.7428 33.2898 40.7302 33.2981 40.7093 33.2939C40.6632 33.3064 40.6277 33.321 40.6025 33.3377C40.5565 33.3502 40.5021 33.3502 40.4394 33.3375C40.2218 33.3372 39.9624 33.3285 39.6612 33.3114C39.5106 33.3029 39.2785 33.267 38.9647 33.2039C38.7347 33.1575 38.5695 33.1134 38.4691 33.0714L37.4842 32.7752L37.4278 32.7312ZM36.8947 32.4607L36.9638 32.442C36.9972 32.4922 37.0139 32.5173 37.0139 32.5173L36.9511 32.5047L36.8947 32.4607ZM36.6473 29.6363L36.7791 29.6302L36.9987 29.6744C37.2496 29.7249 37.4357 29.7733 37.557 29.8195L38.5106 30.1093C38.5733 30.122 38.6235 30.143 38.6611 30.1723L38.4979 30.1721C38.3348 30.1175 38.0546 30.0502 37.6572 29.9702L37.6635 29.9388C37.2955 29.8212 36.9965 29.7392 36.7664 29.6929L36.6473 29.6363ZM38.623 30.5237L38.6544 30.53L39.0685 30.5807L39.0999 30.5871L39.0935 30.6184L38.648 30.5614L38.623 30.5237ZM39.275 31.014C39.4423 31.0477 39.5804 31.0646 39.6892 31.0648L39.7205 31.0711C39.6996 31.0669 39.6913 31.0543 39.6955 31.0334L39.4885 30.9264C39.4049 30.9096 39.3442 30.8865 39.3066 30.8572C39.2857 30.853 39.271 30.8718 39.2626 30.9136C39.2542 30.9554 39.2395 30.9742 39.2186 30.97C39.2144 30.9909 39.2332 31.0056 39.275 31.014ZM41.9788 31.8521L42.0792 31.8397C42.1002 31.8439 42.1085 31.8565 42.1043 31.8774L42.0352 31.8961L41.9788 31.8521ZM43.0591 31.1883C43.1009 31.1967 43.1344 31.1926 43.1595 31.1759L43.2286 31.1571L43.1972 31.1508L43.0654 31.1569L43.0591 31.1883ZM42.8157 30.1274C42.9245 30.1275 43.0709 30.1026 43.2551 30.0526L43.3178 30.0653L43.2488 30.084C43.1776 30.1132 43.1085 30.1319 43.0416 30.1402C42.9746 30.1485 42.9077 30.1568 42.8407 30.1651L42.8094 30.1587L42.8157 30.1274ZM44.2821 31.7609C44.3449 31.7736 44.4118 31.7653 44.483 31.7361C44.5499 31.7278 44.6064 31.7174 44.6525 31.7049C44.6734 31.7091 44.6859 31.7008 44.6901 31.6799L44.6965 31.6485L44.6023 31.6295C44.5563 31.642 44.5103 31.6545 44.4642 31.667C44.4391 31.6837 44.414 31.7004 44.3889 31.7171C44.347 31.7087 44.3136 31.7128 44.2884 31.7296L44.2257 31.7169L44.2194 31.7483L44.2821 31.7609ZM43.0342 30.9874C43.0676 31.0377 43.1095 31.0461 43.1597 31.0127C43.2978 30.9752 43.3794 30.9481 43.4046 30.9314L43.4987 30.9504C43.5489 30.917 43.5741 30.9002 43.5741 30.9002L43.5614 30.963C43.5572 30.9839 43.5551 30.9944 43.5551 30.9944C43.576 30.9986 43.5865 31.0007 43.5865 31.0007C43.5656 30.9965 43.5551 30.9944 43.5551 30.9944C43.5509 31.0153 43.5488 31.0257 43.5488 31.0257C43.5028 31.0382 43.4379 31.0361 43.3543 31.0192C43.35 31.0401 43.3375 31.0485 43.3166 31.0443C43.3375 31.0485 43.3479 31.0506 43.3479 31.0506C43.3437 31.0715 43.3416 31.082 43.3416 31.082L43.4357 31.1009C43.4357 31.1009 43.4483 31.0925 43.4734 31.0758C43.4943 31.0801 43.5006 31.1031 43.4922 31.1449C43.5131 31.1491 43.5256 31.1408 43.5298 31.1198C43.5843 31.0655 43.6471 31.0238 43.7183 30.9946L43.7623 30.9381L43.7686 30.9068C43.7895 30.911 43.823 30.9068 43.869 30.8943C43.9318 30.907 43.9819 30.928 44.0196 30.9573C43.9944 30.974 43.9693 30.9907 43.9442 31.0074C43.9149 31.045 43.8918 31.0513 43.8751 31.0261L43.8374 31.0512L43.8688 31.0575L43.9316 31.0701L44.0194 31.1205L43.9126 31.1643C43.8917 31.1601 43.877 31.1789 43.8686 31.2207C43.8644 31.2416 43.8727 31.2542 43.8937 31.2584C43.9773 31.2752 44.061 31.2377 44.1448 31.1457L44.0884 31.1017L44.1261 31.0767L44.1952 31.0579L44.4211 31.0708L44.4587 31.0457C44.4672 31.0039 44.4839 30.9746 44.5091 30.9579C44.5551 30.9454 44.5865 30.9517 44.6032 30.9769C44.6157 31.0229 44.6554 31.0418 44.7223 31.0335L45.1617 30.9587C45.2036 30.9672 45.2308 30.94 45.2434 30.8773L45.1746 30.7328C45.1412 30.6826 45.114 30.6554 45.0931 30.6512L45.024 30.6699C45.0198 30.6908 45.0052 30.7096 44.98 30.7263L44.9173 30.7137C44.8964 30.7095 44.8441 30.6989 44.7604 30.6821C44.6977 30.6695 44.6412 30.6799 44.591 30.7133C44.5407 30.7467 44.4633 30.7529 44.3587 30.7318C44.296 30.7192 44.2311 30.717 44.1642 30.7253C44.1139 30.7587 44.07 30.7607 44.0324 30.7314C44.0115 30.7272 43.9885 30.7334 43.9633 30.7501C43.9591 30.771 43.9466 30.7794 43.9257 30.7752L43.8692 30.7312L43.5679 30.7685C43.547 30.7642 43.5366 30.7621 43.5366 30.7621C43.5324 30.783 43.5303 30.7935 43.5303 30.7935C43.5051 30.8102 43.4926 30.8186 43.4926 30.8186C43.5093 30.8437 43.5176 30.8562 43.5176 30.8562L43.4235 30.8373L43.3545 30.856C43.3042 30.8894 43.2477 30.8998 43.185 30.8872C43.1641 30.883 43.141 30.8892 43.1159 30.9059C43.1117 30.9269 43.0991 30.9352 43.0782 30.931L43.0532 30.8933L43.0469 30.9247L43.0342 30.9874ZM44.6463 31.5731L44.6213 31.5354L44.5209 31.5479L44.5773 31.5919L44.6463 31.5731ZM44.264 31.2024C44.2849 31.2066 44.3414 31.1962 44.4335 31.1712L44.7097 31.0962C44.7306 31.1005 44.7432 31.0921 44.7474 31.0712L44.716 31.0649C44.6491 31.0732 44.5926 31.0835 44.5465 31.096C44.5005 31.1085 44.444 31.1189 44.3771 31.1272L44.3457 31.1209L44.2202 31.0956L44.2139 31.127C44.2473 31.1772 44.264 31.2024 44.264 31.2024ZM44.0886 30.9386L44.1514 30.9512C44.1179 30.9009 44.1012 30.8758 44.1012 30.8758L44.0448 30.8318C44.0448 30.8318 44.0699 30.8151 44.1202 30.7817C44.2959 30.7736 44.4256 30.7779 44.5093 30.7948C44.5344 30.778 44.5574 30.7718 44.5783 30.776C44.6159 30.8053 44.6473 30.8117 44.6724 30.795L44.6975 30.8326L44.6849 30.8954L44.5844 30.9078L44.4716 30.8198C44.4088 30.8072 44.3837 30.8239 44.3962 30.8699C44.3878 30.9117 44.3459 30.9577 44.2705 31.0078C44.2454 31.0245 44.214 31.0182 44.1764 30.9889C44.1555 30.9847 44.1346 30.9805 44.1137 30.9762L44.0196 30.9573L44.0886 30.9386ZM45.0919 31.6302L45.5376 31.524L45.6066 31.5053L45.5752 31.499C45.3995 31.5071 45.2865 31.5279 45.2363 31.5613L45.0291 31.6175L44.8723 31.586C44.8053 31.5942 44.7635 31.5858 44.7468 31.5607C44.751 31.5398 44.7322 31.5251 44.6903 31.5167C44.6861 31.5376 44.6945 31.5502 44.7154 31.5544C44.7112 31.5753 44.7195 31.5879 44.7405 31.5921C44.7614 31.5963 44.7697 31.6088 44.7655 31.6297C44.7529 31.6925 44.7717 31.7072 44.8219 31.6737L45.0919 31.6302ZM44.823 30.8579L44.7478 30.7448L44.7164 30.7385L44.6474 30.7573C44.6725 30.7406 44.706 30.7364 44.7478 30.7448L44.7792 30.7512C44.821 30.7596 44.8795 30.7931 44.9548 30.8518C44.9506 30.8727 44.938 30.8811 44.9171 30.8769C44.9129 30.8978 44.8899 30.904 44.848 30.8956L44.8167 30.8893L44.823 30.8579ZM45.4003 30.9088L45.5321 30.9027C45.5572 30.886 45.5635 30.8547 45.551 30.8086C45.5552 30.7877 45.5594 30.7668 45.5637 30.7459L45.4883 30.796L45.482 30.8274L45.4066 30.8775C45.4066 30.8775 45.3982 30.8649 45.3815 30.8398C45.3606 30.8356 45.3523 30.823 45.3565 30.8021C45.3649 30.7603 45.3377 30.733 45.275 30.7204L45.2687 30.7518C45.3188 30.8272 45.3439 30.8648 45.3439 30.8648L45.3375 30.8962L45.4003 30.9088ZM45.4323 30.4257L45.4072 30.388L45.2942 30.4631L45.2878 30.4945L45.4323 30.4257ZM45.7329 30.8779C45.7538 30.8821 45.7664 30.8737 45.7706 30.8528C45.7706 30.8528 45.7957 30.8361 45.846 30.8027C45.8711 30.786 45.915 30.784 45.9778 30.7966L45.9904 30.7339L45.959 30.7276C45.8837 30.7777 45.8565 30.7504 45.8776 30.6459C45.8776 30.6459 45.8818 30.625 45.8902 30.5831L45.8651 30.5454C45.8191 30.5579 45.7835 30.5725 45.7584 30.5892C45.75 30.6311 45.7541 30.6645 45.7708 30.6897L45.7832 30.7901C45.7665 30.765 45.7373 30.7482 45.6955 30.7398L45.6704 30.7021L45.6327 30.7271C45.6285 30.7481 45.6369 30.7606 45.6578 30.7648C45.6996 30.7733 45.687 30.7816 45.6201 30.7899C45.6159 30.8108 45.6138 30.8213 45.6138 30.8213C45.6347 30.8255 45.6451 30.8276 45.6451 30.8276C45.6618 30.8527 45.6911 30.8695 45.7329 30.8779ZM45.6769 30.5076C45.702 30.4908 45.7251 30.4846 45.746 30.4888C45.7878 30.4972 45.8213 30.4931 45.8464 30.4764L45.79 30.4324L45.6832 30.4762C45.6832 30.4762 45.6811 30.4866 45.6769 30.5076ZM46.0399 31.2988L46.0839 31.2423L46.0525 31.236C46.0191 31.1858 46.0024 31.1606 46.0024 31.1606C46.0233 31.1649 46.0359 31.1565 46.0401 31.1356C46.061 31.1398 46.0819 31.144 46.1029 31.1482C46.1447 31.1566 46.1614 31.1818 46.153 31.2236L46.1843 31.2299C46.2262 31.2383 46.2722 31.2258 46.3224 31.1924C46.3936 31.1632 46.4439 31.1298 46.4732 31.0922L46.5046 31.0985L46.5673 31.1112L46.944 31.0238L46.9816 30.9987L46.9189 30.9861C46.6261 30.9271 46.396 30.9352 46.2285 31.0103L45.9523 31.0853C45.9523 31.0853 45.9419 31.0832 45.9209 31.079C45.9209 31.079 45.9188 31.0894 45.9146 31.1103C45.8728 31.1019 45.8059 31.1102 45.7138 31.1352C45.6929 31.131 45.6824 31.1289 45.6824 31.1289C45.6782 31.1498 45.6761 31.1602 45.6761 31.1602L45.7011 31.1979C45.8057 31.219 45.8873 31.2463 45.9458 31.2798L46.0399 31.2988ZM46.5172 31.0358L46.6176 31.0234L46.6427 31.061C46.6385 31.082 46.6259 31.0903 46.605 31.0861C46.5632 31.0777 46.5297 31.0818 46.5046 31.0985L46.5172 31.0358ZM46.3302 30.0189C46.3302 30.0189 46.3679 29.9938 46.4433 29.9437C46.4642 29.9479 46.4789 29.9291 46.4873 29.8873L46.4997 29.9877C46.4997 29.9877 46.4746 30.0044 46.4243 30.0378L46.3866 30.0629L46.3803 30.0942C46.397 30.1194 46.4179 30.1236 46.4431 30.1069C46.4891 30.0944 46.5163 30.0672 46.5248 30.0254C46.5374 29.9627 46.5667 29.925 46.6128 29.9125C46.6337 29.9168 46.6462 29.9084 46.6504 29.8875L46.6191 29.8812L46.525 29.8622C46.4831 29.8538 46.435 29.8768 46.3805 29.9311L46.3052 29.9812L46.167 30.0187L46.098 30.0374L46.1544 30.0814L46.3302 30.0189ZM46.8882 30.4903C46.8924 30.4694 46.884 30.4568 46.8631 30.4526C46.8213 30.4442 46.7878 30.4483 46.7627 30.465L46.7187 30.5214C46.7354 30.5466 46.7458 30.5487 46.75 30.5277L46.8882 30.4903ZM47.1198 30.9612C47.0988 30.957 47.0905 30.9445 47.0947 30.9236C47.0445 30.957 47.0193 30.9737 47.0193 30.9737L47.013 31.005L47.1198 30.9612ZM46.8444 30.3835C46.8653 30.3877 46.8778 30.3794 46.882 30.3585C46.903 30.3627 46.9218 30.3773 46.9385 30.4025C46.9552 30.4276 46.9656 30.4297 46.9698 30.4088C46.9908 30.413 47.0117 30.4172 47.0326 30.4214C47.0577 30.4047 47.0912 30.4006 47.133 30.409C47.1372 30.3881 47.1184 30.3734 47.0766 30.365C47.0305 30.3775 46.9448 30.3711 46.8193 30.3458L46.7816 30.3709L46.8444 30.3835ZM47.1585 30.1203L47.2275 30.1016L47.1962 30.0953L47.1774 30.0262C47.1983 30.0304 47.2109 30.0221 47.2151 30.0012L47.1837 29.9949L47.0079 30.0574L47.0016 30.0888L47.0267 30.1264L47.1585 30.1203ZM47.4783 30.3153C47.5285 30.2819 47.5537 30.2652 47.5537 30.2652L47.673 30.1586C47.7149 30.1671 47.7588 30.165 47.8048 30.1525C47.876 30.1233 47.9137 30.0983 47.9179 30.0774L47.9305 30.0146C47.9263 30.0355 47.9138 30.0439 47.8928 30.0397C47.8426 30.0731 47.807 30.0877 47.7861 30.0835L47.7924 30.0521L47.7987 30.0207L47.6983 30.0332L47.692 30.0645L47.673 30.1586C47.6312 30.1502 47.6103 30.146 47.6103 30.146L47.4972 30.2212L47.4532 30.2776L47.4783 30.3153ZM46.6631 29.8248C46.7049 29.8332 46.7279 29.8269 46.7321 29.806C46.8242 29.781 46.9665 29.7226 47.1591 29.6308L47.4793 29.4995L47.9126 29.2929L48.2015 29.1552C48.2015 29.1552 48.2119 29.1573 48.2329 29.1615C48.258 29.1448 48.2622 29.1239 48.2455 29.0988C48.2246 29.0946 48.2392 29.0758 48.2895 29.0424L48.2832 29.0737L48.3396 29.1177C48.4903 29.0175 48.5657 28.9674 48.5657 28.9674L48.572 28.936L48.5407 28.9297C48.5407 28.9297 48.5155 28.9464 48.4653 28.9798C48.2811 29.0298 48.1639 29.0715 48.1137 29.1049L47.3602 29.4428C47.2764 29.5348 47.1759 29.6016 47.0587 29.6433L46.9896 29.662L46.6694 29.7934C46.6485 29.7892 46.6359 29.7975 46.6317 29.8184L46.6631 29.8248ZM47.6233 29.7569C47.6233 29.7569 47.6212 29.7674 47.617 29.7883C47.6379 29.7925 47.6505 29.7842 47.6547 29.7633C47.6798 29.7466 47.7091 29.7633 47.7425 29.8136C47.7634 29.8178 47.7843 29.822 47.8053 29.8262C47.8262 29.8304 47.8304 29.8095 47.8179 29.7635C47.8221 29.7425 47.8556 29.7384 47.9183 29.751L47.9497 29.7574L48.0061 29.8014L48.0438 29.7763C48.048 29.7554 48.0418 29.7324 48.0251 29.7072C48.0084 29.6821 47.977 29.6758 47.9309 29.6883L47.6297 29.7256L47.6233 29.7569ZM48.5207 29.8397L48.7468 29.6893L48.8535 29.6455L48.8598 29.6142L48.8285 29.6079L48.6527 29.6704C48.6485 29.6913 48.6254 29.6975 48.5836 29.6891L48.5899 29.6578L48.4455 29.7266C48.4664 29.7308 48.4727 29.7538 48.4642 29.7957L48.4516 29.8584L48.5207 29.8397ZM46.5746 25.4003C46.5537 25.396 46.5453 25.3835 46.5495 25.3626L46.5181 25.3563L46.3741 25.0988L46.3428 25.0925L46.255 25.0421L46.2236 25.0358C46.2236 25.0358 46.2215 25.0463 46.2173 25.0672C46.2173 25.0672 46.2277 25.0693 46.2486 25.0735L46.5055 25.419L46.5746 25.4003ZM45.2289 22.518C45.2332 22.4971 45.2457 22.4887 45.2666 22.4929C45.2332 22.4427 45.2165 22.4176 45.2165 22.4176L45.1788 22.4426C45.1788 22.4426 45.1955 22.4677 45.2289 22.518ZM45.417 22.7191L45.3669 22.6437L45.3418 22.606L45.3544 22.5433C45.3126 22.5348 45.2791 22.539 45.254 22.5557L45.2791 22.5934C45.3125 22.6436 45.3271 22.6792 45.3229 22.7001L45.3793 22.7441L45.417 22.7191ZM45.7802 23.3471C45.7844 23.3262 45.7865 23.3157 45.7865 23.3157C45.8074 23.3199 45.8178 23.322 45.8178 23.322L45.774 23.2153L45.705 23.234L45.7802 23.3471ZM46.3 24.1699L46.3063 24.1385C46.2436 24.1259 46.2164 24.0986 46.2248 24.0568C46.2333 24.015 46.1956 23.9856 46.112 23.9688C46.0285 23.8432 45.9867 23.7804 45.9867 23.7804L45.9553 23.7741L45.9867 23.7804L46.112 23.9688L46.2686 24.1635L46.3 24.1699ZM46.0747 23.6675C46.058 23.6424 46.0434 23.6068 46.0309 23.5608C46.0226 23.4938 45.9871 23.454 45.9244 23.4414C45.9244 23.4414 45.9139 23.4393 45.893 23.4351C45.8972 23.4142 45.9098 23.4058 45.9307 23.41L45.937 23.3787L45.9056 23.3723C45.9014 23.3933 45.8868 23.4121 45.8616 23.4288C45.8574 23.4497 45.8658 23.4622 45.8867 23.4665L46.0684 23.6989L46.0747 23.6675ZM49.0672 29.3948C49.0714 29.3739 49.0631 29.3613 49.0422 29.3571C49.0255 29.332 49.0192 29.309 49.0234 29.288L48.9417 29.3695L48.9542 29.4699L49.0672 29.3948ZM46.4819 24.2391L46.4505 24.2328C46.4463 24.2537 46.4547 24.2663 46.4756 24.2705L46.5821 24.3899L46.6135 24.3962L46.4819 24.2391ZM46.3758 23.7934L46.2128 23.63L46.1815 23.6237L46.2002 23.6928C46.2336 23.743 46.2817 23.7745 46.3444 23.7871L46.3695 23.8248L46.3758 23.7934ZM46.6891 24.1829L46.6139 24.0699L46.5825 24.0635L46.6577 24.1766L46.6891 24.1829ZM46.7893 24.3337L46.7518 24.1955L46.7455 24.2269L46.7141 24.2206L46.7579 24.3273L46.7893 24.3337ZM48.479 28.1012C48.5208 28.1097 48.5438 28.1034 48.548 28.0825L48.7428 27.9259C48.7679 27.9091 48.7868 27.8694 48.7994 27.8067C48.8078 27.7649 48.8037 27.7314 48.787 27.7063C48.7745 27.6602 48.7536 27.656 48.7242 27.6936L48.4602 28.0322L48.479 28.1012ZM47.0838 24.6541L47.0902 24.6227L46.9523 24.497L46.9459 24.5284L47.0525 24.6478L47.0838 24.6541ZM47.0529 24.3214C46.8774 24.112 46.7437 23.9654 46.6518 23.8816C46.656 23.8607 46.6477 23.8482 46.6267 23.8439C46.6225 23.8649 46.6309 23.8774 46.6518 23.8816L46.94 24.2334L47.0466 24.3528L47.1093 24.3654L47.0529 24.3214ZM46.6648 23.4926L46.552 23.4045L46.5206 23.3982C46.554 23.4485 46.5812 23.4757 46.6021 23.4799L46.6648 23.4926ZM46.6651 23.3294C46.6651 23.3294 46.686 23.3336 46.7278 23.342L46.7341 23.3106L46.6777 23.2666C46.6109 23.1661 46.5461 23.1096 46.4834 23.0969L46.4583 23.0593L46.4457 23.122L46.6651 23.3294ZM47.5037 25.163C47.533 25.1253 47.5644 25.1317 47.5978 25.1819L47.6292 25.1882L47.6041 25.1505L47.5226 25.0688L47.4912 25.0625L47.4786 25.1253C47.4744 25.1462 47.4723 25.1566 47.4723 25.1566C47.4932 25.1609 47.5037 25.163 47.5037 25.163ZM48.944 27.5747C48.9691 27.558 48.9734 27.5371 48.9567 27.5119C48.9442 27.4659 48.9275 27.4408 48.9065 27.4366C48.9065 27.4366 48.894 27.4449 48.8689 27.4616C48.8437 27.4783 48.8291 27.4971 48.8249 27.518L48.9063 27.5997L48.944 27.5747ZM48.7954 26.0432L48.5697 25.8672L48.018 25.3644C47.9637 25.31 47.8968 25.2639 47.8174 25.2261C47.7631 25.1717 47.7004 25.1046 47.6294 25.0251C47.5541 24.9664 47.4998 24.9119 47.4664 24.8617C47.433 24.8114 47.3975 24.7716 47.3599 24.7423L47.1655 24.5726C47.1655 24.5726 47.1488 24.5475 47.1154 24.4972L46.7958 24.1391L46.7644 24.1328L46.7581 24.1642C46.8082 24.2395 46.8876 24.3317 46.9963 24.4406C47.0297 24.4909 47.0547 24.5285 47.0714 24.5537C47.1133 24.5621 47.1446 24.5684 47.1655 24.5726C47.1822 24.5977 47.1885 24.6208 47.1843 24.6417C47.1801 24.6626 47.1884 24.6751 47.2093 24.6794C47.3389 24.7925 47.529 24.9831 47.7797 25.2512L48.1934 25.6282L48.2749 25.7099C48.325 25.7853 48.4023 25.8335 48.5069 25.8546C48.5278 25.8588 48.5362 25.8713 48.532 25.8922C48.5654 25.9425 48.5821 25.9676 48.5821 25.9676C48.6155 26.0179 48.6698 26.0723 48.745 26.131L48.8015 26.175L48.7954 26.0432ZM46.4214 22.4316C46.4299 22.3898 46.4257 22.3563 46.409 22.3312L46.4153 22.2998C46.3234 22.2161 46.2816 22.1532 46.2901 22.1114L46.2587 22.1051C46.2587 22.1051 46.2482 22.103 46.2273 22.0988C46.2273 22.0988 46.2252 22.1092 46.221 22.1302C46.3045 22.2558 46.3463 22.3186 46.3463 22.3186C46.3672 22.3228 46.3755 22.3354 46.3713 22.3563C46.3713 22.3563 46.388 22.3814 46.4214 22.4316ZM48.1995 25.76L48.118 25.6783L48.0804 25.7034C48.1097 25.6658 48.1055 25.6323 48.0679 25.603C48.0512 25.5779 48.0429 25.5653 48.0429 25.5653L47.9801 25.5527C47.9886 25.5108 47.974 25.4753 47.9363 25.4459C47.9196 25.4208 47.9008 25.4061 47.8799 25.4019C47.8799 25.4019 47.8695 25.3998 47.8485 25.3956C47.8485 25.3956 47.8464 25.4061 47.8422 25.427C47.8631 25.4312 47.8715 25.4437 47.8673 25.4647C47.9091 25.4731 47.9279 25.4877 47.9237 25.5087C47.9445 25.6216 47.9967 25.6866 48.0804 25.7034L48.0991 25.7725L48.1932 25.7914L48.1995 25.76ZM48.5067 26.0177L48.488 25.9487L48.3187 25.8167L48.2873 25.8104L48.2747 25.8731L48.444 26.0051L48.5067 26.0177ZM49.1327 27.2862C49.1578 27.2695 49.1767 27.2298 49.1893 27.1671C49.2019 27.1043 49.1999 27.0604 49.1832 27.0353L49.1204 27.0226L49.0891 27.0163L49.1017 26.9536C49.1017 26.9536 49.0766 26.9703 49.0263 27.0037L48.9823 27.0601C48.9571 27.1856 48.9842 27.2672 49.0636 27.305L49.1327 27.2862ZM47.4929 23.7572C47.472 23.753 47.4615 23.7509 47.4615 23.7509C47.4657 23.73 47.4679 23.7195 47.4679 23.7195C47.4093 23.686 47.3612 23.6545 47.3236 23.6252C47.3069 23.6001 47.2902 23.5749 47.2735 23.5498L47.2108 23.5372L47.2045 23.5685L47.4239 23.7759L47.4929 23.7572ZM48.7638 26.2001L48.6509 26.1121L48.5694 26.0304L48.5381 26.024L48.5318 26.0554L48.7198 26.2565L48.7825 26.2691L48.7638 26.2001ZM47.7938 24.0462C47.7604 23.996 47.7332 23.9688 47.7123 23.9646L47.6809 23.9582C47.6725 24.0001 47.6892 24.0252 47.731 24.0336L47.7938 24.0462ZM48.928 25.3844C48.9364 25.3426 48.9302 25.3196 48.9092 25.3154L48.8278 25.2337L48.7463 25.152L48.4705 24.9006C48.4371 24.8504 48.3827 24.7959 48.3075 24.7372C48.2365 24.6576 48.1864 24.5823 48.1572 24.5111L48.1258 24.5048C48.084 24.4964 48.0317 24.4859 47.969 24.4732C47.9062 24.4606 47.8581 24.4292 47.8247 24.3789C47.7704 24.3244 47.6847 24.2637 47.5677 24.1966C47.5719 24.1757 47.5635 24.1631 47.5426 24.1589L47.5613 24.2279L47.787 24.404C48.2132 24.8815 48.4263 25.1202 48.4263 25.1202L48.5141 25.1705C48.5225 25.1287 48.535 25.1203 48.5517 25.1455C48.5727 25.1497 48.5831 25.1518 48.5831 25.1518C48.6416 25.1853 48.6793 25.2147 48.696 25.2398C48.7336 25.2691 48.7607 25.2963 48.7774 25.3215L48.8652 25.3718L48.928 25.3844ZM49.4904 27.293L49.503 27.2302L49.4843 27.1612L49.4716 27.2239L49.4339 27.249L49.4213 27.3117L49.4464 27.3494L49.4904 27.293ZM48.1888 24.3543L48.1073 24.2726L48.0759 24.2663L48.1323 24.3103C48.1323 24.3103 48.149 24.3354 48.1824 24.3856L48.1888 24.3543ZM49.4032 26.7531C49.4032 26.7531 49.4241 26.7573 49.4659 26.7658L49.4472 26.6967L49.2842 26.5333L49.2215 26.5207L49.2402 26.5898C49.2736 26.64 49.328 26.6945 49.4032 26.7531ZM45.9978 19.9961L46.0104 19.9334L46.0984 19.8205L46.1111 19.7578L46.0797 19.7515C46.0504 19.7891 46.0106 19.8246 45.9603 19.858C45.9352 19.8747 45.9268 19.9165 45.9351 19.9835L45.9475 20.0839L45.9978 19.9961ZM50.8932 29.5665L50.9436 29.4788C50.8933 29.5122 50.8682 29.5289 50.8682 29.5289L50.8305 29.5539L50.8242 29.5853L50.8932 29.5665ZM49.7919 27.0925L49.5788 26.8538L49.516 26.8411L49.5662 26.9165L49.7165 27.1426L49.7729 27.1866L49.7919 27.0925ZM46.2168 20.5298C46.2377 20.5341 46.2502 20.5257 46.2544 20.5048L46.2357 20.4357L46.242 20.4044C46.2504 20.3625 46.2693 20.3228 46.2987 20.2852C46.3322 20.2267 46.3427 20.1744 46.3302 20.1283L46.3366 20.097L46.4372 19.9214L46.4184 19.8523C46.3557 19.8397 46.3201 19.8543 46.3117 19.8961L46.2864 20.0216L46.2738 20.0843C46.2026 20.1135 46.1544 20.1909 46.1292 20.3164L46.1416 20.4168L46.1353 20.4482C46.1144 20.4439 46.1018 20.4523 46.0976 20.4732C46.1143 20.4983 46.1184 20.5318 46.11 20.5736L46.2168 20.5298ZM48.9842 25.5916L48.9341 25.5162L48.9027 25.5099L48.9151 25.6103L48.9842 25.5916ZM47.6011 22.5712C47.5844 22.5461 47.5551 22.5293 47.5133 22.5209L47.4632 22.4455C47.4716 22.4037 47.4591 22.3577 47.4257 22.3074C47.4048 22.3032 47.3986 22.2802 47.407 22.2383L47.4573 22.1506L47.5074 22.2259L47.6451 22.5148L47.6325 22.5775L47.6011 22.5712ZM48.7846 24.6374L48.7595 24.5997C48.7637 24.5788 48.7554 24.5663 48.7345 24.5621C48.6759 24.5285 48.6279 24.4971 48.5903 24.4677C48.5736 24.4426 48.5568 24.4175 48.5401 24.3924L48.5088 24.386L48.5025 24.4174C48.5234 24.4216 48.5965 24.4908 48.7218 24.6248L48.7846 24.6374ZM48.9598 25.0644L48.8595 24.9137L48.8282 24.9073L48.8219 24.9387L48.9221 25.0895L48.9535 25.0958L48.9598 25.0644ZM50.2302 27.8336C50.2344 27.8127 50.2365 27.8022 50.2365 27.8022C50.2574 27.8064 50.2679 27.8086 50.2679 27.8086C50.2888 27.8128 50.3097 27.817 50.3306 27.8212C50.3558 27.8045 50.3391 27.7794 50.2805 27.7458C50.2638 27.7207 50.2429 27.7165 50.2178 27.7332C50.1969 27.729 50.1843 27.7373 50.1801 27.7582C50.1801 27.7582 50.1906 27.7603 50.2115 27.7645C50.2324 27.7688 50.2407 27.7813 50.2365 27.8022L50.2302 27.8336ZM49.9738 27.1618C49.978 27.1409 49.9905 27.1325 50.0115 27.1367C50.0199 27.0949 50.0366 27.0656 50.0618 27.0489L50.0681 27.0176L50.0117 26.9736L49.999 27.0363L49.9864 27.099L49.955 27.0927L49.9738 27.1618ZM49.5737 25.9061C49.5779 25.8852 49.5696 25.8726 49.5487 25.8684L49.0722 25.4787L49.0471 25.4411C49.0387 25.4829 49.045 25.5059 49.0659 25.5101L49.2352 25.6421L49.511 25.8935L49.5737 25.9061ZM51.0697 29.0145L51.076 28.9831C51.0342 28.9747 51.0132 28.9705 51.0132 28.9705C51.0384 28.9538 51.0614 28.9476 51.0823 28.9518L51.1012 28.8577L51.1076 28.8263L50.9694 28.8638L50.9631 28.8951L50.9505 28.9579C50.9296 28.9537 50.917 28.962 50.9128 28.9829L50.9692 29.0269L51.0697 29.0145ZM46.4624 19.7959C46.4667 19.775 46.4792 19.7666 46.5001 19.7708L46.4814 19.7018L46.4123 19.7205L46.4624 19.7959ZM50.0251 26.2581L50.0064 26.1891L50.0127 26.1577C50.0587 26.1452 50.0441 26.1096 49.9689 26.051L49.8937 25.9379C49.8645 25.8667 49.8374 25.8395 49.8123 25.8562C49.7495 25.8436 49.7245 25.8059 49.7371 25.7432L49.712 25.7055L49.687 25.6678L49.6807 25.6992L49.6744 25.7305L49.5929 25.6488C49.5929 25.6488 49.5824 25.6467 49.5615 25.6425C49.5615 25.6425 49.5636 25.6321 49.5678 25.6112L49.5992 25.6175L49.6306 25.6238L49.6055 25.5861L49.3611 25.341C49.2106 25.2237 49.0956 25.1462 49.0162 25.1084C48.9909 25.2339 49.0097 25.3029 49.0724 25.3156C49.11 25.3449 49.1163 25.3679 49.0911 25.3846C49.0827 25.4265 49.1099 25.4537 49.1726 25.4663L49.2604 25.5166C49.3021 25.6338 49.4108 25.7427 49.5863 25.8434C49.6282 25.8518 49.6428 25.8874 49.6301 25.9501C49.6259 25.971 49.6322 25.9941 49.6489 26.0192C49.6865 26.0485 49.7179 26.0548 49.743 26.0381C49.7639 26.0423 49.7744 26.0444 49.7744 26.0444C49.7786 26.0235 49.7807 26.0131 49.7807 26.0131L49.787 25.9817L49.8184 25.988L49.8057 26.0508L49.8245 26.1198C49.8496 26.1031 49.8601 26.1052 49.8558 26.1261C49.9186 26.1388 49.9436 26.1765 49.931 26.2392L49.9624 26.2455L50.0251 26.2581ZM49.2861 25.0648L49.1796 24.9454C49.1796 24.9454 49.1691 24.9433 49.1482 24.9391C49.1482 24.9391 49.1461 24.9496 49.1419 24.9705C49.1419 24.9705 49.1398 24.981 49.1356 25.0019C49.1356 25.0019 49.146 25.004 49.1669 25.0082L49.2547 25.0585L49.2861 25.0648ZM50.3997 27.8024C50.4499 27.769 50.4855 27.7544 50.5064 27.7586C50.5316 27.7419 50.5567 27.7252 50.5818 27.7085C50.6321 27.6751 50.6426 27.6228 50.6134 27.5517L50.6511 27.5266C50.6553 27.5057 50.6825 27.4786 50.7328 27.4452L50.7391 27.4138C50.7182 27.4096 50.7056 27.4179 50.7014 27.4388C50.5758 27.5224 50.513 27.5641 50.513 27.5641C50.4543 27.6393 50.4312 27.7 50.4437 27.746L50.4374 27.7774L50.3997 27.8024ZM49.5432 25.2471C49.5013 25.2387 49.4428 25.2052 49.3676 25.1465L49.4741 25.2659L49.5432 25.2471ZM50.0571 25.7749C50.0529 25.7959 50.0508 25.8063 50.0508 25.8063C50.0759 25.7896 50.0885 25.7813 50.0885 25.7813C50.0969 25.7394 50.0802 25.7143 50.0384 25.7059C50.0217 25.6808 50.0029 25.6661 49.9819 25.6619L50.0571 25.7749ZM50.6772 26.7485C50.6522 26.6564 50.623 26.5852 50.5896 26.535C50.5938 26.5141 50.5875 26.4911 50.5708 26.4659C50.5541 26.4408 50.5374 26.4157 50.5207 26.3906L50.483 26.4156L50.4704 26.4784C50.4954 26.5704 50.5246 26.6416 50.558 26.6918L50.5767 26.7609L50.6332 26.8049L50.6772 26.7485ZM50.4081 26.1394C50.4248 26.1645 50.4395 26.1457 50.4521 26.083C50.4145 26.0536 50.379 26.0138 50.3456 25.9636C50.3122 25.9133 50.2578 25.8589 50.1826 25.8002L50.1199 25.7876L50.1386 25.8566C50.1595 25.8608 50.1679 25.8734 50.1636 25.8943C50.2264 25.907 50.2661 25.9258 50.2828 25.951L50.4081 26.1394ZM51.4097 28.1363C51.4139 28.1154 51.4264 28.1071 51.4474 28.1113L51.4412 27.9795L51.3659 28.0296C51.3617 28.0505 51.3763 28.0861 51.4097 28.1363ZM50.1078 25.3608C49.9908 25.2937 49.9156 25.2351 49.8821 25.1848C49.8612 25.1806 49.8529 25.168 49.8571 25.1471L49.8885 25.1534L50.1392 25.3671L50.1078 25.3608ZM50.8715 26.9182C50.8757 26.8973 50.8883 26.8889 50.9092 26.8931L50.8905 26.8241L50.8656 26.6232C50.8489 26.5981 50.8448 26.5646 50.8532 26.5228L50.5649 26.171C50.5231 26.1625 50.5022 26.1583 50.5022 26.1583C50.4813 26.1541 50.4666 26.1729 50.4582 26.2148L50.4833 26.2524C50.6128 26.3656 50.7068 26.4933 50.7652 26.6356L50.8214 26.8428C50.813 26.8846 50.8297 26.9097 50.8715 26.9182ZM45.8717 20.4604C45.8926 20.4646 45.9073 20.4458 45.9157 20.4039C45.9241 20.3621 45.9492 20.3454 45.9911 20.3538C46.058 20.3456 46.0748 20.3163 46.0414 20.266L46.054 20.2033C46.1796 20.1198 46.2216 20.0194 46.1799 19.9022C46.159 19.898 46.1506 19.8854 46.1549 19.8645L46.2805 19.7266L46.4565 19.5009C46.4817 19.4842 46.4984 19.455 46.5069 19.4131C46.5404 19.3546 46.5697 19.317 46.5949 19.3003L46.8273 19.1186C46.8524 19.1019 46.8776 19.0852 46.9027 19.0685C46.9278 19.0518 46.932 19.0309 46.9153 19.0057L46.9467 19.012L47.1854 18.799L47.4179 18.6173L48.203 18.1225C48.2239 18.1267 48.2343 18.1288 48.2343 18.1288C48.2385 18.1079 48.2406 18.0974 48.2406 18.0974L48.1716 18.1162L48.1339 18.1412C47.7697 18.329 47.5875 18.4229 47.5875 18.4229L47.2044 18.7049C47.1792 18.7216 47.0997 18.7926 46.9656 18.9179L46.9029 18.9053C46.928 18.8886 46.9427 18.8698 46.9469 18.8489C46.9553 18.807 46.9721 18.7778 46.9972 18.7611C47.0181 18.7653 47.0411 18.759 47.0663 18.7423C47.0914 18.7256 47.106 18.7068 47.1103 18.6859C47.1187 18.6441 47.1355 18.6148 47.1606 18.5981L47.3176 18.4665L47.3867 18.4478C47.4621 18.3977 47.4998 18.3726 47.4998 18.3726C47.5667 18.3643 47.6756 18.3101 47.8263 18.2099C47.8765 18.1765 47.9163 18.141 47.9457 18.1033C47.9959 18.0699 48.0462 18.0365 48.0964 18.0031C48.1006 17.9822 48.1132 17.9738 48.1341 17.9781C48.1508 18.0032 48.1717 18.0074 48.1968 17.9907C48.2262 17.9531 48.2408 17.9343 48.2408 17.9343L48.2848 17.8778C48.3476 17.8905 48.3832 17.8759 48.3916 17.834L48.4293 17.809C48.4711 17.8174 48.4941 17.8112 48.4983 17.7903L48.6428 17.7214C48.8438 17.5878 48.9443 17.521 48.9443 17.521C48.9485 17.5 48.9401 17.4875 48.9192 17.4833C48.9192 17.4833 48.9171 17.4937 48.9129 17.5146C48.9129 17.5146 48.9024 17.5125 48.8815 17.5083C48.6387 17.6335 48.4587 17.717 48.3415 17.7587L48.0463 17.9277C47.9625 18.0197 47.7992 18.1283 47.5564 18.2535L47.2235 18.4476L47.0978 18.5855L46.8277 18.7922L46.6267 18.9803C46.4508 19.0972 46.3586 19.2309 46.35 19.3816C46.3417 19.3146 46.3125 19.2978 46.2622 19.3312C46.216 19.4525 46.1511 19.5591 46.0673 19.651C46.0673 19.651 46.084 19.6762 46.1174 19.7264C46.1174 19.7264 46.1425 19.7097 46.1927 19.6763L46.2117 19.5822L46.3563 19.3502L46.4254 19.3314L46.6768 19.0556C46.727 19.0222 46.7626 19.0076 46.7835 19.0118C46.7584 19.0285 46.7416 19.0578 46.7332 19.0996C46.6829 19.133 46.6536 19.1707 46.6452 19.2125C46.5447 19.2793 46.4798 19.3315 46.4504 19.3691L46.1801 19.7391C46.1172 19.8352 46.0438 19.9836 45.9599 20.1843L45.9536 20.2157C45.9578 20.1948 45.9494 20.1822 45.9285 20.178C45.9327 20.1571 45.9244 20.1446 45.9035 20.1403L45.8972 20.1717C45.8803 20.2554 45.8572 20.316 45.8279 20.3536C45.8237 20.3745 45.8383 20.4101 45.8717 20.4604ZM47.0477 18.5101C47.232 18.3514 47.433 18.2177 47.6507 18.1092C47.68 18.0716 47.7407 18.0403 47.8328 18.0153L48.1029 17.8086C48.1029 17.8086 48.1281 17.7919 48.1783 17.7585L48.1156 17.7458L48.0465 17.7646C47.9209 17.8481 47.7974 17.9211 47.676 17.9838C47.5755 18.0506 47.475 18.1174 47.3745 18.1842C47.2991 18.2343 47.1818 18.3304 47.0227 18.4724C47.0018 18.4682 46.9871 18.487 46.9787 18.5289L47.0477 18.5101ZM48.1585 18.5053C48.1794 18.5095 48.2276 18.4865 48.303 18.4364L48.2716 18.4301L48.1272 18.4989L48.1585 18.5053ZM48.5981 18.2673C48.5981 18.2673 48.6609 18.2256 48.7866 18.1421L48.7552 18.1357L48.5731 18.2296C48.594 18.2339 48.6023 18.2464 48.5981 18.2673ZM49.2331 17.3833L49.2017 17.3769L49.0259 17.4395L49.051 17.4772L49.2331 17.3833ZM50.5334 16.4373L50.6024 16.4185L50.6715 16.3998C50.6882 16.4249 50.6923 16.4584 50.6839 16.5002L50.6776 16.5316C50.6651 16.4856 50.6358 16.4688 50.5898 16.4813C50.5689 16.4771 50.548 16.4729 50.5271 16.4687L50.458 16.4874L50.5334 16.4373ZM55.6026 17.6863C55.7699 17.72 55.9373 17.6993 56.1047 17.6242C56.155 17.5908 56.1822 17.5636 56.1864 17.5427L56.2681 17.4612L56.2243 17.3545C56.0988 17.3292 56.0131 17.3228 55.967 17.3353C55.9043 17.3227 55.8373 17.331 55.7662 17.3602C55.6992 17.3685 55.6553 17.3705 55.6344 17.3663C55.6135 17.3621 55.6009 17.3704 55.5967 17.3914L55.6281 17.3977L55.6845 17.4417C55.7012 17.4668 55.6949 17.4982 55.6655 17.5358C55.6362 17.5734 55.609 17.6006 55.5838 17.6173L55.5712 17.68L55.6026 17.6863ZM54.7205 35.5924C54.6996 35.5882 54.6912 35.5757 54.6954 35.5547C54.6787 35.5296 54.6788 35.4752 54.6956 35.3916L54.6457 35.153C54.625 35.04 54.5477 34.9374 54.4139 34.8452L54.3575 34.8012C54.2781 34.7635 54.2489 34.6923 54.2699 34.5877L54.2703 34.2614C54.2663 34.1735 54.2852 34.0794 54.3272 33.9791C54.3565 33.9415 54.3817 33.8704 54.4027 33.7658C54.4406 33.5776 54.5036 33.427 54.5916 33.3142L54.7489 33.0194C54.7531 32.9985 54.7615 32.9567 54.7741 32.8939C54.7825 32.8521 54.7805 32.8082 54.768 32.7621L54.8057 32.7371C54.856 32.7037 54.8874 32.6556 54.9 32.5929L54.9127 32.5301L54.919 32.4988C54.8981 32.4945 54.8855 32.5029 54.8813 32.5238L54.7996 32.6053L54.655 32.8373C54.655 32.8373 54.6445 32.8352 54.6236 32.831C54.6194 32.8519 54.6089 32.8498 54.5922 32.8247L54.5545 32.8497C54.479 33.0086 54.4119 33.1257 54.3533 33.2009C54.3448 33.2427 54.3281 33.272 54.3029 33.2887L54.3219 33.1946C54.3303 33.1528 54.3408 33.1005 54.3535 33.0377C54.387 32.9792 54.4331 32.9123 54.4918 32.8371C54.5169 32.8204 54.5337 32.7911 54.5421 32.7493L54.5674 32.6238L54.7562 32.1722L54.8821 31.8711L54.8634 31.8021C54.8592 31.823 54.8466 31.8313 54.8257 31.8271C54.7795 31.9484 54.6935 32.1052 54.5678 32.2975C54.442 32.4898 54.3204 32.7155 54.2029 32.9748L53.9953 33.3574L53.989 33.3887L53.9703 33.3197C54.0374 33.2026 54.0772 33.1127 54.0899 33.05C54.157 32.9329 54.1989 32.8325 54.2158 32.7489C54.2409 32.7322 54.2451 32.7113 54.2284 32.6861C54.1908 32.6568 54.1615 32.64 54.1406 32.6358C54.1197 32.6316 54.1113 32.6191 54.1155 32.5981L54.2288 32.3598L54.2667 32.1716C54.2709 32.1507 54.2626 32.1381 54.2417 32.1339L54.204 32.159L54.16 32.2154L54.1223 32.2404L54.1349 32.1777L54.2229 32.0648C54.2313 32.023 54.2649 31.9645 54.3235 31.8892C54.3613 31.8098 54.376 31.7366 54.3678 31.6697C54.3511 31.6445 54.3574 31.6132 54.3867 31.5755C54.3909 31.5546 54.393 31.5442 54.393 31.5442L54.3743 31.4751L54.3052 31.4939L54.0286 31.8951L53.9972 31.8888C53.9763 31.8846 53.9701 31.8616 53.9785 31.8198C54.0036 31.8031 54.0246 31.7529 54.0414 31.6692L54.1044 31.5187L54.205 31.3431L54.249 31.2867C54.291 31.1863 54.3812 31.0086 54.5195 30.7536L54.5259 30.7222C54.5049 30.718 54.4924 30.7264 54.4882 30.7473L54.3311 30.8789L54.2871 30.9353C54.2662 30.9311 54.2536 30.9394 54.2494 30.9603C54.2578 30.9185 54.2621 30.8976 54.2621 30.8976C54.3291 30.7805 54.3899 30.6949 54.4444 30.6405L54.589 30.4085L54.7713 30.1514L54.828 30.0323C54.8322 30.0114 54.8343 30.0009 54.8343 30.0009C54.8134 29.9967 54.8008 30.005 54.7966 30.026L54.7652 30.0196C54.7317 30.0782 54.6521 30.1492 54.5265 30.2327L54.4008 30.3706L54.3128 30.4835L54.2688 30.5399L53.9231 30.9599L53.9168 30.9913L53.9294 30.9286L54.4764 30.1573L54.8724 29.6495C54.8808 29.6077 54.9143 29.5492 54.973 29.4739L54.9793 29.4426C54.9584 29.4383 54.9459 29.4467 54.9416 29.4676C54.7908 29.6766 54.6902 29.7978 54.64 29.8312C54.6357 29.8521 54.6232 29.8605 54.6023 29.8563L54.6086 29.8249L54.6526 29.7685L54.6652 29.7057L54.6275 29.7308L54.5962 29.7245L54.6591 29.5739C54.6842 29.5572 54.7094 29.5405 54.7345 29.5238C54.7638 29.4862 54.7953 29.4381 54.8288 29.3796L54.9357 29.1726L55.093 28.8779C55.1517 28.8026 55.1852 28.7441 55.1937 28.7023L55.3949 28.3511C55.4243 28.3135 55.4536 28.2759 55.4829 28.2383C55.5165 28.1797 55.55 28.1212 55.5836 28.0627L55.7532 27.8683L55.7596 27.837C55.8057 27.7157 55.9168 27.5422 56.0928 27.3165C56.1306 27.2371 56.2039 27.143 56.3128 27.0344C56.4679 26.8045 56.5476 26.679 56.5518 26.6581L56.7278 26.4324C56.7823 26.3781 56.7887 26.2923 56.747 26.1751L56.7284 25.9429L56.7537 25.8174C56.712 25.7002 56.7058 25.6228 56.7352 25.5852L56.7415 25.5538L56.6478 25.2086L56.5916 25.0014L56.5855 24.8696C56.5647 24.7566 56.5774 24.6395 56.6236 24.5182C56.7033 24.3384 56.7934 24.2151 56.8939 24.1483L57.1324 24.0984C57.3249 24.1154 57.5257 24.0905 57.735 24.0238C57.8522 23.9821 58.0238 23.9405 58.2498 23.899L58.2874 23.8739C58.3711 23.8908 58.4465 23.8406 58.5136 23.7236L58.7336 23.4415L58.9285 23.1216C59.1339 22.8583 59.2533 22.6974 59.2869 22.6389C59.3455 22.5636 59.3791 22.5051 59.3875 22.4633L59.5258 22.2626C59.5551 22.225 59.6306 22.1205 59.7521 21.9491L59.922 21.5916L60.1924 21.2217C60.2972 21.0252 60.4041 20.8726 60.513 20.764L61.0539 19.861C61.1796 19.6687 61.2635 19.5223 61.3054 19.422L61.4815 19.1963L61.5821 19.0207L61.4063 19.0832L60.973 19.2898L60.9353 19.3148C60.9227 19.3776 60.8745 19.4005 60.7909 19.3837C60.7281 19.371 60.6738 19.371 60.6277 19.3835C60.5022 19.3582 60.4206 19.3853 60.3829 19.4647C60.3535 19.5024 60.3158 19.5274 60.2698 19.5399C60.2489 19.5357 60.2196 19.5189 60.182 19.4896C60.1319 19.4142 60.0608 19.389 59.9687 19.414L59.8683 19.4264C59.8265 19.418 59.7972 19.4012 59.7805 19.3761C59.7429 19.3468 59.7074 19.307 59.674 19.2567C59.6657 19.1898 59.6679 19.1249 59.6805 19.0622C59.7182 18.9828 59.7561 18.8489 59.794 18.6607C59.8233 18.6231 59.8485 18.552 59.8695 18.4474L59.8698 18.2843L59.8824 18.2215C60.0375 17.9916 60.1423 17.8495 60.1967 17.7952L60.3224 17.6573C60.4187 17.6114 60.4795 17.5257 60.5047 17.4002C60.5216 17.3165 60.5677 17.2497 60.643 17.1995C60.7184 17.1494 60.7415 17.0888 60.7123 17.0176C60.704 16.9507 60.7229 16.911 60.7689 16.8985C61.0033 16.8151 61.177 16.763 61.29 16.7422C61.3612 16.713 61.401 16.6775 61.4094 16.6357L61.3907 16.5666L61.3593 16.5603L61.397 16.5353L61.6669 16.4917L62.213 16.3731C62.2549 16.3816 62.2883 16.3774 62.3135 16.3607C62.4431 16.3651 62.6419 16.3507 62.9097 16.3175L63.2487 16.2552L63.5876 16.1929C63.6337 16.1804 63.709 16.1847 63.8135 16.2057L64.0645 16.2563C64.1063 16.2647 64.1774 16.2899 64.2778 16.3318C64.3991 16.378 64.4973 16.4304 64.5726 16.4891L64.8046 16.6337L64.9111 16.7531L64.9675 16.7971C65.047 16.8349 65.1641 16.8476 65.3189 16.8352L65.5699 16.8857C65.5908 16.89 65.6222 16.8963 65.664 16.9047C65.7058 16.9131 65.7519 16.9006 65.8021 16.8672L65.8335 16.8735L66.1598 16.8739L66.3104 16.9369C66.645 17.0043 66.9022 17.0778 67.082 17.1575C67.1614 17.1953 67.2848 17.231 67.4521 17.2647C67.5692 17.3318 67.6591 17.3716 67.7218 17.3843C67.7804 17.4178 67.8619 17.4451 67.9665 17.4662C68.0835 17.5332 68.163 17.571 68.2048 17.5794C68.28 17.6381 68.3595 17.6758 68.4431 17.6927C68.5184 17.7514 68.5664 17.7828 68.5874 17.787C68.8883 18.0217 69.0659 18.1662 69.1202 18.2207C69.4462 18.5475 69.6655 18.8092 69.7782 19.006C69.9619 19.2824 70.1038 19.5503 70.2039 19.8098C70.2373 19.8601 70.2769 19.9877 70.3227 20.1928L70.3976 20.469C70.431 20.5193 70.4414 20.5758 70.4288 20.6385C70.4371 20.7055 70.437 20.7599 70.4286 20.8017C70.3991 20.9481 70.3885 21.0548 70.3968 21.1217C70.4135 21.1468 70.4155 21.1908 70.4029 21.2535L70.2829 21.8496L70.1629 22.4456C70.1335 22.592 70.0516 22.7822 69.9174 23.0164C69.8001 23.1668 69.7016 23.2776 69.6221 23.3486C69.4042 23.5659 69.2304 23.7267 69.1006 23.8312L68.6923 24.0754L68.4536 24.2885C68.3573 24.3344 68.2694 24.3928 68.1898 24.4639L67.5868 24.8647L67.1032 25.1591L66.5819 25.4785C66.5819 25.4785 66.494 25.537 66.3181 25.6539C66.1758 25.7123 66.0439 25.7728 65.9225 25.8354C65.8053 25.8771 65.7111 25.9125 65.64 25.9417L65.1816 26.1106L64.422 26.3167L63.7754 26.4477L63.0912 26.6037L62.8903 26.6285L62.7899 26.641C62.3588 26.7283 62.1099 26.7761 62.0429 26.7843L61.2645 26.9214L60.7624 26.9835L60.1912 27.0644C60.1033 27.0685 59.9673 27.0955 59.7832 27.1455C59.7623 27.1413 59.7141 27.1642 59.6388 27.2143C59.513 27.4066 59.4082 27.5487 59.3244 27.6407L59.2364 27.7535L58.9347 28.1171L58.5387 28.625L58.413 28.7629L58.1804 29.1077L57.9227 29.4149L57.778 29.6469L57.6334 29.8789C57.5412 30.0127 57.4511 30.136 57.3631 30.2489C57.3002 30.345 57.2394 30.4307 57.1808 30.5059L57.0424 30.7066L56.9544 30.8194L56.5018 31.4464C56.3887 31.576 56.2943 31.7202 56.2188 31.8791C55.9253 32.3641 55.743 32.6755 55.6717 32.8135L55.3508 33.4344C55.2669 33.6351 55.2123 33.7982 55.187 33.9237C55.1408 34.045 55.0904 34.2415 55.0356 34.5134L54.9662 34.8585C54.9367 35.0049 54.9031 35.1178 54.8653 35.1972C54.8485 35.2809 54.8023 35.4022 54.7268 35.5611L54.7205 35.5924ZM53.6305 34.0347C53.5971 33.9844 53.5867 33.9279 53.5993 33.8652L53.6056 33.8338C53.6266 33.838 53.6391 33.8297 53.6433 33.8088L53.6684 33.8464C53.66 33.8883 53.6641 33.9217 53.6808 33.9469C53.6599 33.9427 53.6473 33.951 53.6431 33.9719L53.6242 34.066L53.6305 34.0347ZM53.7246 34.0536C53.7246 34.0536 53.7267 34.0432 53.7309 34.0222C53.7309 34.0222 53.7205 34.0201 53.6995 34.0159L53.7436 33.9595L53.7686 33.9972L53.7246 34.0536ZM54.4015 34.7448L54.3828 34.6757L54.3388 34.7322L54.3952 34.7762L54.4015 34.7448ZM54.1644 33.6525L54.177 33.5898L54.2337 33.4706L54.2587 33.5083C54.2294 33.5459 54.2084 33.5961 54.1958 33.6588C54.1958 33.6588 54.1853 33.6567 54.1644 33.6525C54.1644 33.6525 54.1623 33.663 54.1581 33.6839L54.1644 33.6525ZM54.3478 32.5796L54.285 32.567L54.241 32.6234L54.2975 32.6674L54.3478 32.5796ZM60.1905 22.6902L60.1718 22.6212L60.0901 22.7026C60.111 22.7069 60.1193 22.7194 60.1151 22.7403L60.1905 22.6902ZM62.3736 23.3582C62.3862 23.2955 62.4219 23.2265 62.4805 23.1513L62.5372 23.0321L62.5435 23.0007L62.5749 23.007L62.5936 23.0761C62.5643 23.1137 62.5328 23.1618 62.4993 23.2203C62.4699 23.2579 62.4385 23.306 62.405 23.3645C62.405 23.3645 62.3945 23.3624 62.3736 23.3582C62.3736 23.3582 62.3715 23.3687 62.3673 23.3896L62.3736 23.3582ZM63.3418 21.9537C63.4508 21.8451 63.522 21.7615 63.5555 21.7029L63.6875 21.5337C63.8595 21.2201 63.9622 21.034 63.9958 20.9755C64.0042 20.9337 64.0293 20.917 64.0711 20.9254C64.092 20.9296 64.1004 20.9422 64.0962 20.9631C64.1129 20.9882 64.1317 21.0029 64.1526 21.0071L64.008 21.2391C63.8906 21.3896 63.811 21.515 63.769 21.6153C63.7481 21.6111 63.7355 21.6195 63.7313 21.6404C63.6602 21.6696 63.5848 21.7197 63.5052 21.7907C63.4465 21.866 63.4025 21.9224 63.3732 21.96C63.369 21.9809 63.3418 22.0081 63.2915 22.0415L63.3418 21.9537ZM62.2791 23.6656L62.7561 23.5658L63.4404 23.4098C63.4864 23.3973 63.5994 23.3765 63.7794 23.3475L64.3381 23.1662C64.4051 23.1579 64.5097 23.1246 64.6521 23.0662L64.9283 22.9912L65.4243 22.7973L66.0334 22.5282C66.2678 22.4448 66.4352 22.3697 66.5357 22.3029L67.057 21.9835L67.2078 21.8833L67.4465 21.6702L67.7733 21.3443C67.9115 21.198 68.0079 21.0434 68.0625 20.8803C68.1003 20.8008 68.1381 20.667 68.176 20.4788L68.1887 20.416C68.2055 20.3324 68.1805 20.2403 68.1137 20.1398C67.9256 19.9931 67.8232 19.9072 67.8065 19.8821C67.7647 19.8737 67.6727 19.7899 67.5307 19.6307L67.1795 19.4295L66.8534 19.2659L66.822 19.2596C66.8053 19.2344 66.7698 19.1946 66.7155 19.1402L66.6214 19.1212C66.6005 19.117 66.5921 19.1045 66.5963 19.0835L66.6277 19.0899L66.6591 19.0962C66.6633 19.0753 66.6549 19.0627 66.634 19.0585C66.6382 19.0376 66.6194 19.0229 66.5776 19.0145L66.5839 18.9831L66.6153 18.9894L66.6216 18.9581C66.6007 18.9539 66.5797 18.9496 66.5588 18.9454C66.5421 18.9203 66.5212 18.9161 66.4961 18.9328L66.402 18.9139C66.3183 18.897 66.2389 18.8593 66.1636 18.8006C66.0884 18.7419 66.0299 18.7084 65.9881 18.7C65.9086 18.6622 65.8417 18.6705 65.7872 18.7248L65.4981 19.0257L65.0644 19.5586L64.8821 19.8156C64.7481 19.941 64.6685 20.012 64.6434 20.0287C64.5304 20.0495 64.4299 20.1163 64.3419 20.2291L63.8955 20.8248L63.5246 21.3703L63.1159 21.9409L62.9587 22.2356L62.6883 22.6055C62.6381 22.6389 62.6192 22.6787 62.6317 22.7247L62.6254 22.7561L62.4997 22.894C62.3866 23.0235 62.2336 23.243 62.0407 23.5523C62.0156 23.5691 62.0093 23.6004 62.0218 23.6465C62.0218 23.6465 62.0197 23.6569 62.0155 23.6778C62.0364 23.682 62.0594 23.6758 62.0845 23.6591L62.2791 23.6656ZM69.6424 34.5489C69.5797 34.5363 69.5191 34.5132 69.4605 34.4797C69.4229 34.4503 69.3727 34.4294 69.31 34.4167C69.2724 34.3874 69.2201 34.3769 69.1531 34.3851C69.0904 34.3725 69.0193 34.3473 68.9399 34.3096L68.5887 34.1083L68.5259 34.0957C68.5219 34.0078 68.4822 33.9345 68.407 33.8759C68.3317 33.8172 68.2774 33.7627 68.244 33.7125C68.1688 33.6538 68.104 33.5973 68.0497 33.5428C68.0205 33.4716 67.9766 33.4193 67.9181 33.3857C67.9056 33.3397 67.8827 33.2916 67.8492 33.2413C67.8158 33.1911 67.7845 33.1304 67.7553 33.0592L67.8118 33.1032L67.5553 32.4314C67.4886 32.2221 67.4807 31.8832 67.5315 31.4147L67.4439 31.2012C67.4272 31.1761 67.421 31.153 67.4252 31.1321C67.4545 31.0945 67.4713 31.0652 67.4755 31.0443C67.501 30.7013 67.5243 30.4775 67.5454 30.3729C67.6001 30.101 67.6548 29.8835 67.7094 29.7204C67.7091 29.938 67.6984 30.0991 67.6774 30.2036L67.7088 30.21C67.7382 30.0636 67.7573 29.8607 67.766 29.6013L67.7346 29.595C67.7262 29.6368 67.7095 29.6661 67.6843 29.6828C67.6636 29.5698 67.6763 29.3983 67.7226 29.1682C67.7732 28.9172 67.8236 28.7207 67.874 28.5785C67.9202 28.4572 68.0356 28.154 68.2203 27.6689C68.2539 27.6104 68.2937 27.5205 68.3399 27.3992C68.4112 27.2613 68.4553 27.1504 68.4721 27.0668C68.4847 27.004 68.4869 26.9392 68.4786 26.8722C68.4955 26.7886 68.5228 26.707 68.5605 26.6276C68.808 26.1551 69.0469 25.7789 69.2774 25.4989C69.4199 25.3317 69.5519 25.108 69.6736 24.8279C69.7323 24.7526 69.791 24.6774 69.8496 24.6022C69.9334 24.5102 70.0193 24.4078 70.1073 24.295C70.166 24.2198 70.2163 24.132 70.2583 24.0316C70.3254 23.9145 70.4008 23.81 70.4846 23.7181C70.6104 23.5258 70.7005 23.4025 70.7549 23.3482C70.7843 23.3106 70.8074 23.2499 70.8242 23.1663L70.8305 23.1349L71.2893 22.6397L71.7101 22.3327C71.928 22.1155 72.0641 21.9797 72.1186 21.9253C72.2484 21.8209 72.3866 21.729 72.5331 21.6497C72.7006 21.5746 72.8492 21.4849 72.979 21.3804L73.5694 21.0423C73.7955 20.892 73.986 20.8106 74.1408 20.7983C74.6932 20.6484 75.1034 20.5568 75.3712 20.5237L75.6223 20.4111C75.7395 20.3694 75.8923 20.3675 76.0805 20.4054L76.7456 20.5066C76.8711 20.5319 76.9925 20.4693 77.1098 20.3188L77.2481 20.1182L77.2858 20.0931L77.3172 20.0994C77.3799 20.1121 77.4259 20.154 77.4551 20.2251C77.5094 20.2796 77.5407 20.3403 77.549 20.4072L77.6115 20.583C77.6156 20.6709 77.6427 20.7525 77.6928 20.8279C77.7429 20.9033 77.7847 20.9661 77.8181 21.0163C77.839 21.0205 77.8473 21.0331 77.8431 21.054C77.7929 21.0874 77.7803 21.1502 77.8052 21.2422C77.7968 21.2841 77.8051 21.351 77.8301 21.4431L77.8678 21.418C77.8971 21.3804 77.9223 21.3093 77.9434 21.2048L78.0124 21.186L78.4764 21.4753C78.5559 21.513 78.6291 21.5278 78.696 21.5195C78.7212 21.5028 78.7546 21.4986 78.7965 21.5071C78.8592 21.5197 78.8989 21.5386 78.9156 21.5637C78.9533 21.593 78.9909 21.6224 79.0285 21.6517L79.0535 21.6894C79.179 21.7147 79.1832 21.7481 79.066 21.7898L79.3984 21.922C79.5489 22.0394 79.6492 22.1357 79.6993 22.2111C79.7995 22.3618 79.8559 22.4602 79.8683 22.5063C79.8766 22.5732 79.9058 22.6444 79.9559 22.7198C80.006 22.7951 80.0478 22.8579 80.0812 22.9082L80.056 23.0337C80.1437 23.1384 80.2168 23.2075 80.2753 23.241C80.3339 23.2746 80.4008 23.2663 80.4762 23.2162C80.4551 23.3208 80.4613 23.3982 80.4947 23.4484C80.549 23.5029 80.5846 23.5427 80.6013 23.5678C80.6765 23.6265 80.7078 23.6872 80.6952 23.7499C80.6867 23.7917 80.6804 23.8231 80.6762 23.844L80.6886 23.9445C80.7803 24.2458 80.7946 24.5533 80.7314 24.867L80.6301 25.5321C80.5628 25.8668 80.4032 26.3351 80.1514 26.9373L79.8053 27.6837C79.6627 27.9596 79.5662 28.1687 79.5158 28.3109L79.3836 28.6433L79.3396 28.6997L79.3649 28.5743L79.1952 28.7686C79.1323 28.8647 79.0401 28.9985 78.9185 29.1699C78.8221 29.3246 78.688 29.5043 78.5162 29.7091C78.0763 30.1646 77.7893 30.455 77.6553 30.5803C77.4835 30.7851 77.3076 30.9564 77.1275 31.0943L77.1085 31.1884C77.1504 31.1968 77.1734 31.1905 77.1776 31.1696C77.1985 31.1738 77.255 31.1634 77.3471 31.1385C77.2591 31.2513 77.1711 31.3098 77.0833 31.3138C76.8406 31.3303 76.6417 31.4534 76.4866 31.6834C76.4404 31.8046 76.3252 31.9446 76.1409 32.1034C75.337 32.6379 74.935 32.9051 74.935 32.9051C74.935 32.9051 74.6084 33.1223 73.9551 33.5566C73.93 33.5733 73.9132 33.6025 73.9048 33.6444C73.9006 33.6653 73.8859 33.6841 73.8608 33.7008L73.7351 33.8387L73.5088 34.1522C73.379 34.2566 73.2723 34.246 73.1888 34.1204L73.0822 34.001L73.0132 34.0198C72.6488 34.3164 72.4268 34.5002 72.3472 34.5712L72.2152 34.7405L72.1651 34.6651C72.1651 34.6651 72.14 34.6818 72.0898 34.7152L71.9704 34.8218L71.8512 34.7651C71.8094 34.7567 71.7257 34.7942 71.6 34.8778C71.5958 34.8987 71.5728 34.9049 71.531 34.8965C71.5101 34.8923 71.4996 34.8902 71.4996 34.8902C71.4704 34.819 71.4224 34.7876 71.3554 34.7959C71.2884 34.8041 71.2341 34.8041 71.1922 34.7957C71.0165 34.8038 70.8596 34.7722 70.7217 34.7009C70.7008 34.6967 70.6485 34.6862 70.5648 34.6693C70.5021 34.6567 70.4456 34.6671 70.3953 34.7005C70.3493 34.713 70.2845 34.7108 70.2008 34.694L69.6424 34.5489ZM67.8395 31.0197C67.8437 30.9988 67.8333 30.9423 67.8084 30.8502L67.777 30.8439C67.8271 30.9193 67.8479 30.9779 67.8395 31.0197ZM69.2369 32.672C69.262 32.6553 69.2725 32.6574 69.2683 32.6783C69.2892 32.6825 69.3101 32.6867 69.331 32.6909L69.7578 32.6789C69.7244 32.6287 69.6972 32.6014 69.6763 32.5972C69.6345 32.5888 69.5717 32.5762 69.4881 32.5593C69.4086 32.5216 69.3354 32.5068 69.2685 32.5151C69.2224 32.5276 69.1471 32.5233 69.0426 32.5023C68.9631 32.4645 68.8899 32.4498 68.823 32.4581C68.7812 32.4497 68.731 32.4287 68.6724 32.3951C68.6348 32.3658 68.5992 32.3804 68.5657 32.4389L68.5343 32.4326C68.4549 32.3949 68.3399 32.3173 68.1895 32.2L67.9701 31.9926C67.9951 32.0847 68.0452 32.16 68.1204 32.2187C68.1162 32.2396 68.1203 32.2731 68.1328 32.3191C68.1495 32.3443 68.183 32.3401 68.2333 32.3067C68.2457 32.3528 68.2729 32.38 68.3147 32.3884C68.3775 32.401 68.4067 32.4178 68.4025 32.4387C68.4192 32.4638 68.4485 32.4806 68.4903 32.489L68.7977 32.5836L68.7476 32.5082L69.0424 32.6655L69.2369 32.672ZM69.2742 32.9733C69.2408 32.923 69.2032 32.8937 69.1613 32.8853L69.155 32.9166L69.2742 32.9733ZM68.4164 31.397L68.2785 31.2713C68.3077 31.3424 68.3306 31.3906 68.3473 31.4157L68.4101 31.4283L68.4164 31.397ZM68.0713 31.3275L68.084 31.2648C68.1049 31.269 68.1132 31.2815 68.109 31.3024C68.1299 31.3066 68.1487 31.3213 68.1654 31.3464C68.1614 31.2586 68.1259 31.1644 68.0591 31.0639C68.0132 30.9676 68.007 30.8902 68.0406 30.8317L67.9968 30.7249C68.001 30.704 67.9926 30.6915 67.9717 30.6872C67.9844 30.6245 67.9823 30.5806 67.9656 30.5554L68.0785 30.6434C68.0368 30.5262 68.0159 30.4676 68.0159 30.4676C67.9952 30.3547 67.9765 30.2312 67.9599 30.0973L67.9286 30.091C67.9119 30.0659 67.9056 30.0429 67.9098 30.0219C67.9182 29.9801 67.9141 29.9466 67.8974 29.9215L67.8785 30.0156L67.8721 30.047L67.9286 30.091C67.9034 30.1077 67.8846 30.1474 67.8719 30.2102C67.8593 30.2729 67.8571 30.3921 67.8652 30.5679C67.8441 30.6724 67.842 30.7373 67.8587 30.7624C67.8877 30.9423 67.9482 31.1286 68.04 31.3212L68.0713 31.3275ZM69.1432 32.3267C69.2478 32.3477 69.3293 32.375 69.3879 32.4086L69.3942 32.3772L68.9051 32.0503L69.1493 32.4585L69.1432 32.3267ZM68.7044 31.9119L68.7609 31.9559C68.8988 32.0272 68.9804 32.0545 69.0055 32.0378C69.0725 32.0296 69.1247 32.0401 69.1624 32.0694C69.2209 32.103 69.2732 32.1135 69.3192 32.101C69.3653 32.0885 69.4301 32.0907 69.5138 32.1075C69.5974 32.1244 69.6623 32.1265 69.7083 32.114L69.7647 32.158L69.9342 32.1269L70.0723 32.0894L70.0786 32.058C70.0995 32.0622 70.1351 32.0476 70.1854 32.0142L68.6293 31.7989L68.6105 31.7298C68.6063 31.7507 68.6042 31.7612 68.6042 31.7612L68.0023 31.3462C68.0023 31.3462 68.0607 31.4342 68.1777 31.61C68.2111 31.6603 68.2466 31.7001 68.2842 31.7294C68.3427 31.763 68.3908 31.7944 68.4284 31.8237L68.2966 31.8298L68.3781 31.9115L68.5036 31.9368L68.7105 32.0437L68.7044 31.9119ZM69.6077 32.2896C69.6453 32.319 69.6662 32.3232 69.6704 32.3023C69.6788 32.2604 69.6851 32.2291 69.6893 32.2082L69.4885 32.233L69.6077 32.2896ZM69.023 33.0859C69.0857 33.0985 69.1673 33.1258 69.2677 33.1678C69.3931 33.1931 69.4894 33.2016 69.5563 33.1933C70.3178 33.1942 70.9351 33.0465 71.4082 32.75L71.4962 32.6372L71.3895 32.681L71.3581 32.6747C71.2869 32.7039 71.2158 32.7331 71.1446 32.7623C71.0944 32.7957 71.0441 32.8291 70.9939 32.8625C70.9438 32.7871 70.9186 32.8038 70.9185 32.9126C70.8976 32.9084 70.8767 32.9042 70.8558 32.9C70.839 32.8748 70.8181 32.8706 70.793 32.8873L70.3913 32.937L70.3473 32.9935C70.2846 32.9808 70.2302 32.9808 70.1841 32.9932C70.1423 32.9848 70.0754 32.9931 69.9833 33.0181L69.6757 33.0867C69.5878 33.0908 69.5125 33.0865 69.4498 33.0739C69.4122 33.0446 69.3724 33.0257 69.3306 33.0173L69.2992 33.0109C69.2365 32.9983 69.1926 33.0004 69.1674 33.0171L69.1047 33.0044L69.0356 33.0232L69.0232 32.9227C69.0023 32.9185 68.9667 32.9331 68.9165 32.9665C68.8913 32.9832 68.8621 32.9665 68.8287 32.9162C68.8329 32.8953 68.8224 32.8932 68.7973 32.9099C68.7889 32.9517 68.7951 32.9747 68.816 32.979C68.8913 33.0376 68.9603 33.0733 69.023 33.0859ZM70.5296 32.7364L70.5359 32.705C70.469 32.7133 70.402 32.7216 70.3351 32.7299C70.289 32.7424 70.243 32.7548 70.197 32.7673L70.1907 32.7987L70.5296 32.7364ZM69.7771 32.2585C69.9947 32.2587 70.1662 32.2715 70.2917 32.2968C70.1746 32.2297 70.0847 32.1898 70.022 32.1772L69.9906 32.1709C69.9529 32.2503 69.8859 32.2586 69.7898 32.1957L69.7207 32.2145L69.7771 32.2585ZM70.4424 32.1966C70.4634 32.2008 70.4634 32.2008 70.4424 32.1966C70.4467 32.1756 70.4488 32.1652 70.4488 32.1652C70.4069 32.1568 70.3735 32.1609 70.3483 32.1776L70.2793 32.1963C70.3211 32.2048 70.342 32.209 70.342 32.209L70.4424 32.1966ZM70.2921 31.9704C70.5599 31.9373 70.857 31.921 71.1833 31.9214L71.1896 31.89L70.3047 31.9077L70.2921 31.9704ZM71.0574 32.2224L71.0324 32.1848C71.0115 32.1805 70.9759 32.1951 70.9256 32.2286L70.957 32.2349L71.0574 32.2224ZM71.7348 32.5873C71.718 32.5622 71.7097 32.5496 71.7097 32.5496C71.7348 32.5329 71.739 32.512 71.7223 32.4869L71.6659 32.4429C71.5654 32.5097 71.5152 32.5431 71.5152 32.5431L71.672 32.5747L71.7348 32.5873ZM72.7812 33.8751L72.7498 33.8688C72.7289 33.8646 72.6933 33.8792 72.643 33.9126C72.664 33.9168 72.6723 33.9294 72.6681 33.9503L72.7812 33.8751ZM71.2901 31.8776C71.311 31.8818 71.3675 31.8714 71.4596 31.8464L71.4659 31.815L71.2901 31.8776ZM71.7788 32.5309C71.783 32.51 71.8102 32.4828 71.8604 32.4494L71.804 32.4054L71.76 32.4618L71.7788 32.5309ZM71.2589 31.7081C71.2798 31.7123 71.3363 31.7019 71.4284 31.6769L71.4033 31.6392L71.2589 31.7081ZM73.138 34.5346C73.1883 34.5011 73.2239 34.4865 73.2448 34.4908C73.2448 34.4908 73.2615 34.5159 73.2949 34.5661L73.138 34.5346ZM71.9044 32.393C71.9169 32.439 71.9357 32.4537 71.9609 32.437C72.0069 32.4245 72.0404 32.4203 72.0613 32.4245L71.9798 32.3429L71.8857 32.3239L71.9044 32.393ZM71.7234 31.671C71.8154 31.646 71.9661 31.6002 72.1754 31.5335L72.1817 31.5022L71.692 31.6647L71.7234 31.671ZM72.4011 31.7095C72.3802 31.7053 72.3697 31.7032 72.3697 31.7032C72.3739 31.6823 72.376 31.6719 72.376 31.6719L72.9098 31.4529L72.9034 31.4843L72.4011 31.7095ZM70.0277 32.6353C70.0946 32.627 70.1825 32.623 70.2913 32.6231C70.4043 32.6023 70.5173 32.5816 70.6303 32.5608C70.9734 32.4775 71.2539 32.3817 71.4716 32.2732L71.7981 32.1104L72.043 32.0291L72.4889 31.7599C72.7024 31.6723 72.8468 31.6034 72.9222 31.5533L73.6193 31.1714L74.0275 30.9271C74.0275 30.9271 74.2159 30.8019 74.5928 30.5513C74.6388 30.5388 74.664 30.5221 74.6682 30.5012C74.6724 30.4803 74.687 30.4615 74.7122 30.4448C74.8629 30.3446 74.9383 30.2945 74.9383 30.2945C75.0137 30.2443 75.0765 30.2026 75.1267 30.1692C75.1812 30.1149 75.2335 30.071 75.2838 30.0376C75.1583 30.0123 75.0641 30.0478 75.0012 30.1439C75.0012 30.1439 74.9991 30.1544 74.9949 30.1753C74.9949 30.1753 74.9845 30.1732 74.9635 30.169C74.9551 30.2108 74.8713 30.3027 74.7122 30.4448L74.5364 30.5073L74.3606 30.5698L74.3669 30.5385L74.2726 30.6827L74.2538 30.6136L74.1408 30.6888C74.1366 30.7097 74.1554 30.7244 74.1972 30.7328C74.1469 30.7662 74.1135 30.7704 74.0968 30.7452C74.0549 30.7368 73.9963 30.7577 73.921 30.8078C73.8707 30.8412 73.8435 30.8683 73.8393 30.8892L73.789 30.977L73.7262 30.9644C73.7471 30.9686 73.7576 30.9707 73.7576 30.9707C73.7618 30.9498 73.7639 30.9394 73.7639 30.9394C73.7472 30.9142 73.6907 30.9246 73.5944 30.9705C73.519 31.0206 73.4562 31.0624 73.406 31.0958C73.3515 31.1501 73.3013 31.1835 73.2552 31.196C73.2092 31.2085 73.1736 31.2231 73.1485 31.2398L72.9601 31.3651L72.8973 31.3525C72.6294 31.4944 72.4159 31.582 72.2569 31.6152C72.1899 31.6235 72.1062 31.6611 72.0057 31.7279L71.9994 31.7592L72.307 31.6906C72.3028 31.7115 72.3007 31.722 72.3007 31.722C72.3216 31.7262 72.332 31.7283 72.332 31.7283L71.1703 32.3104C71.007 32.3646 70.8229 32.4146 70.6178 32.4604C70.4128 32.5061 70.1951 32.5602 69.965 32.6227C69.9817 32.6478 70.0026 32.652 70.0277 32.6353ZM72.2444 31.5148C72.3826 31.4773 72.5144 31.4168 72.64 31.3333L72.5773 31.3207L72.7217 31.2518C72.7469 31.2351 72.7699 31.2289 72.7908 31.2331C72.8368 31.2206 72.862 31.2039 72.8662 31.183L73.042 31.1204C73.0462 31.0995 73.0378 31.087 73.0169 31.0828L72.8662 31.183C72.7323 31.1995 72.6402 31.2245 72.5899 31.2579L72.5773 31.3207C72.4852 31.3457 72.4078 31.3518 72.3451 31.3392L72.3638 31.4083L72.571 31.352C72.4287 31.4104 72.3198 31.4647 72.2444 31.5148ZM73.0919 31.359C73.0667 31.3757 73.0333 31.3798 72.9914 31.3714L72.9601 31.3651L72.9664 31.3337L72.9788 31.4341L73.0919 31.359ZM73.4864 31.9933C73.5158 31.9557 73.5765 31.9244 73.6685 31.8994L73.6372 31.8931C73.6121 31.9098 73.589 31.9161 73.5681 31.9118C73.5472 31.9076 73.5221 31.9243 73.4927 31.962L73.4864 31.9933ZM73.0982 31.3276C73.1233 31.3109 73.1463 31.3047 73.1672 31.3089C73.2133 31.2964 73.251 31.2713 73.2803 31.2337C73.3012 31.2379 73.3096 31.2505 73.3054 31.2714L73.1296 31.3339L73.0982 31.3276ZM73.3875 30.8636C73.5716 30.8136 73.7014 30.7636 73.7767 30.7134C73.7558 30.7092 73.7454 30.7071 73.7454 30.7071C73.7496 30.6862 73.7517 30.6758 73.7517 30.6758L73.3811 30.8949L73.1237 31.039C73.1194 31.0599 73.1278 31.0724 73.1487 31.0766L73.3875 30.8636ZM74.541 31.7813L74.5097 31.775C74.3338 31.8919 74.2458 31.9504 74.2458 31.9504L74.2772 31.9567L74.541 31.7813ZM71.7598 32.625C71.8225 32.6376 71.8665 32.6356 71.8916 32.6189C72.1051 32.5313 72.3123 32.4207 72.5133 32.287C72.6305 32.2454 72.7728 32.187 72.9403 32.1119C73.112 32.0159 73.2689 31.9387 73.4113 31.8803L73.4803 31.8615L73.5683 31.7487L73.9702 31.5358L74.278 31.304L75.0004 30.7966L75.3836 30.5147L75.4716 30.4018L75.6286 30.2702L75.8423 30.0195C76.0015 29.8774 76.1104 29.7688 76.1691 29.6935L76.1817 29.6308L76.119 29.6182L76.031 29.731L75.3147 30.3702C75.2351 30.4413 75.1451 30.5102 75.0446 30.577C74.965 30.648 74.8854 30.719 74.8059 30.7901C74.7556 30.8235 74.6907 30.8757 74.6111 30.9467C74.5567 31.001 74.4813 31.0511 74.385 31.097C74.3557 31.1347 74.295 31.166 74.2029 31.1909L74.2279 31.2286C74.2195 31.2705 74.2027 31.2997 74.1776 31.3164C74.0269 31.4166 73.8929 31.4876 73.7757 31.5293L73.5622 31.6169C73.5622 31.6169 73.5518 31.6148 73.5308 31.6106C73.5308 31.6106 73.5287 31.621 73.5245 31.6419L73.581 31.6859L73.5056 31.736C73.4553 31.7695 73.3842 31.7987 73.2921 31.8236C73.2209 31.8528 73.1372 31.8904 73.0409 31.9363L72.5196 32.2557C72.4945 32.2724 72.2664 32.3788 71.8352 32.5749L71.7598 32.625ZM72.903 31.8106L73.3489 31.5413C73.3238 31.558 73.6064 31.3973 74.1968 31.0591L74.7684 30.652C74.8144 30.6395 74.8438 30.6018 74.8564 30.5391L75.1516 30.37L75.3086 30.2384L75.3966 30.1256C75.4217 30.1089 75.4469 30.0922 75.472 30.0755C75.4971 30.0588 75.5222 30.0421 75.5474 30.0254L75.6731 29.8875C75.6437 29.9251 75.7757 29.8102 76.0689 29.5428L76.0815 29.4801L76.0124 29.4988L75.667 29.7557C75.4491 29.9729 75.3025 30.1066 75.2271 30.1568C75.1727 30.2111 75.0805 30.2904 74.9507 30.3949C74.8418 30.5035 74.7392 30.5808 74.6429 30.6267C74.6429 30.6267 74.2535 30.8856 73.4746 31.4034L72.8403 31.798L72.903 31.8106ZM75.3573 31.456L75.3636 31.4246L74.836 31.7754L74.8924 31.8194L75.3573 31.456ZM75.8727 30.8416L75.8036 30.8604C75.7952 30.9022 75.7993 30.9357 75.816 30.9608L75.8727 30.8416ZM75.3655 29.9561L75.3154 29.8807L75.2023 29.9559C75.1981 29.9768 75.2064 29.9894 75.2273 29.9936L75.3655 29.9561ZM75.6219 30.6279L75.8167 30.4713L75.848 30.4776L75.6533 30.6343L75.6219 30.6279ZM74.9951 30.0121C75.1207 29.9286 75.2883 29.7991 75.4977 29.6237C75.4977 29.6237 75.4998 29.6132 75.504 29.5923C75.4998 29.6132 75.4872 29.6216 75.4663 29.6173C75.3449 29.6799 75.1795 29.799 74.9701 29.9744L74.9638 30.0058L74.9951 30.0121ZM69.7413 30.815C69.8292 30.8109 69.9966 30.7902 70.2435 30.7529C70.2895 30.7404 70.3355 30.7279 70.3816 30.7154C70.4485 30.7071 70.5029 30.7072 70.5447 30.7156C70.7539 30.7577 70.9714 30.758 71.1974 30.7164C71.4276 30.654 71.5762 30.6186 71.6431 30.6103C71.8649 30.5897 72.049 30.5397 72.1956 30.4604L72.924 30.0848L73.5081 29.778C73.5039 29.7989 73.4975 29.8303 73.4891 29.8721C73.5016 29.9182 73.4827 29.9579 73.4325 29.9913C73.4032 30.0289 73.3634 30.0644 73.3131 30.0978C73.288 30.1145 73.2608 30.1417 73.2314 30.1793L72.9173 30.4425C72.9801 30.4551 73.0365 30.4447 73.0868 30.4113L73.2815 30.2547C73.3109 30.2171 73.3486 30.192 73.3946 30.1795C73.4616 30.1712 73.5055 30.1692 73.5264 30.1734C73.6645 30.1359 73.7713 30.0921 73.8466 30.042C73.9471 29.9752 74.0455 29.9189 74.1418 29.873L74.3806 29.6599C74.4559 29.6098 74.5481 29.5304 74.657 29.4218C74.7114 29.3674 74.7868 29.3173 74.8831 29.2714C74.9836 29.2046 75.0444 29.1189 75.0654 29.0144L75.0968 29.0207L75.2539 28.8891L75.769 28.4379C75.9366 28.254 76.0958 28.112 76.2465 28.0118C76.2759 27.9741 76.3073 27.9261 76.3409 27.8675C76.3744 27.809 76.4246 27.7756 76.4916 27.7673L76.5042 27.7046L76.5545 27.6168L76.5922 27.5917L76.5672 27.554C76.5756 27.5122 76.5798 27.4913 76.5798 27.4913L76.8499 27.2845L76.6491 27.3094C76.6993 27.276 76.76 27.2447 76.8312 27.2155C76.9024 27.1863 76.9547 27.1424 76.9882 27.0839C76.9925 27.063 76.9946 27.0525 76.9946 27.0525C77.0155 27.0567 77.0259 27.0588 77.0259 27.0588L77.0636 27.0338L77.0072 26.9898C77.0072 26.9898 76.9967 26.9877 76.9758 26.9835C76.9758 26.9835 76.9779 26.973 76.9821 26.9521L76.9885 26.9207L77.0261 26.8957C77.1056 26.9334 77.1537 26.9105 77.1706 26.8268C77.1706 26.8268 77.2041 26.7683 77.2712 26.6512C77.2754 26.6303 77.2775 26.6199 77.2775 26.6199L77.3278 26.5321C77.3949 26.415 77.4662 26.277 77.5417 26.1181C77.6886 25.8213 77.785 25.6122 77.8312 25.4909C77.9236 25.2484 77.9698 25.0727 77.97 24.9639C77.9784 24.9221 77.9994 24.8719 78.0329 24.8134C78.0665 24.7549 78.0582 24.6879 78.0081 24.6126L78.0144 24.5812C78.0646 24.5478 78.0814 24.5185 78.0647 24.4934C78.048 24.4683 78.0187 24.4515 77.9769 24.4431L77.6318 24.3736L77.7449 24.2984L77.6508 24.2795L77.6194 24.2732L77.0421 24.2222C77.0212 24.218 76.9668 24.2179 76.8789 24.222C76.812 24.2303 76.766 24.1884 76.741 24.0963L76.7096 24.09C76.6929 24.0649 76.6616 24.0586 76.6155 24.0711C76.5737 24.0626 76.534 24.0438 76.4964 24.0144C76.35 23.985 76.2182 23.9911 76.101 24.0328L75.8247 24.1077L75.9439 24.1644C75.7137 24.2268 75.5735 24.2748 75.5233 24.3082L75.4542 24.3269C75.3202 24.4522 75.2176 24.5295 75.1464 24.5587L74.9266 24.6777L74.5876 24.74L74.6064 24.809L74.9013 24.8031C74.8511 24.8366 74.8155 24.8512 74.7946 24.8469C74.7276 24.8552 74.6272 24.8676 74.4933 24.8842C74.3845 24.8841 74.2946 24.8986 74.2234 24.9278C74.1983 24.9445 74.1062 24.9695 73.9472 25.0028C73.8133 25.0193 73.7002 25.0945 73.608 25.2283L73.5076 25.2407C73.4657 25.2323 73.449 25.2071 73.4575 25.1653C73.4743 25.0817 73.4765 25.0168 73.464 24.9708C73.464 24.9708 73.4535 24.9687 73.4326 24.9645C73.4326 24.9645 73.4347 24.954 73.4389 24.9331C73.3553 24.9162 73.2653 24.9308 73.169 24.9767C73.0936 25.0268 73.0434 25.0602 73.0183 25.0769C72.968 25.1103 72.9324 25.1249 72.9115 25.1207C72.8906 25.1165 72.8676 25.1227 72.8425 25.1394C72.8173 25.1561 72.8027 25.1749 72.7985 25.1958C72.7398 25.2711 72.6811 25.3463 72.6225 25.4215C72.568 25.4759 72.5114 25.5406 72.4528 25.6159C71.8074 26.4435 71.424 26.9429 71.3024 27.1143C71.1851 27.2648 70.9336 27.6494 70.5479 28.2681C70.5101 28.3475 70.4598 28.4353 70.3969 28.5315C70.334 28.6276 70.2879 28.6945 70.2586 28.7321L70.0257 29.2402L69.5346 30.5449C69.5219 30.6076 69.5302 30.6746 69.5594 30.7457C69.6137 30.8002 69.6744 30.8233 69.7413 30.815ZM75.7152 31.2996C75.8492 31.1742 75.9812 31.0593 76.111 30.9549C76.266 30.8338 76.4105 30.7105 76.5445 30.5852L76.5131 30.5789C76.4084 30.6666 76.2786 30.771 76.1236 30.8922C75.9938 30.9966 75.8493 31.1198 75.6901 31.2619L75.7152 31.2996ZM75.9478 30.9547C76.0483 30.8879 76.1216 30.8482 76.1676 30.8357C76.1467 30.8315 76.1384 30.819 76.1426 30.798C76.0756 30.8063 76.0107 30.8585 75.9478 30.9547ZM75.6042 29.743C75.5875 29.7179 75.5687 29.7032 75.5478 29.699C75.552 29.6781 75.5541 29.6677 75.5541 29.6677C75.5541 29.6677 75.529 29.6844 75.4787 29.7178C75.4703 29.7596 75.487 29.7847 75.5288 29.7931L75.6042 29.743ZM73.5239 32.1314L73.593 32.1127L74.2964 31.6994L74.3467 31.6116L74.4534 31.5678C74.4786 31.5511 74.4807 31.5406 74.4597 31.5364L74.5288 31.5177L74.5854 31.3985L74.5602 31.524C74.6146 31.4697 74.6796 31.4175 74.7549 31.3674C74.8303 31.3173 74.8743 31.2608 74.8869 31.1981C74.9288 31.2065 74.9748 31.194 75.025 31.1606C75.1171 31.1356 75.2427 31.0521 75.4019 30.9101C75.4815 30.839 75.5736 30.7597 75.6783 30.6719C75.783 30.5842 75.8899 30.486 75.9988 30.3774C76.0741 30.3273 76.0826 30.2854 76.024 30.2519L76.0617 30.2268L76.5895 29.7129C76.8158 29.4538 76.954 29.3075 77.0043 29.2741L77.0357 29.2805C77.0021 29.339 76.9477 29.3933 76.8723 29.4434C76.9475 29.5021 77.0145 29.4938 77.0731 29.4186C77.1569 29.3266 77.2303 29.2326 77.2932 29.1364C77.3602 29.0194 77.4357 28.9149 77.5195 28.8229C77.6159 28.6683 77.6788 28.5721 77.7081 28.5345C77.7123 28.5136 77.7396 28.4864 77.7898 28.453L77.8904 28.2774C78.0162 28.0851 78.077 27.945 78.073 27.8572C78.0772 27.8363 78.0897 27.8279 78.1107 27.8321C78.2238 27.7026 78.2657 27.6022 78.2365 27.5311C78.2952 27.4558 78.3288 27.3973 78.3372 27.3555L78.2557 27.2738L78.174 27.3553C78.1152 27.5393 78.0166 27.7588 77.8782 28.0138L77.8468 28.0075L77.9035 27.8883C77.8532 27.9218 77.8177 27.9363 77.7967 27.9321L77.9414 27.7001C77.9707 27.6625 77.9959 27.5914 78.017 27.4868C77.904 27.5076 77.8454 27.5285 77.8412 27.5494L77.5395 27.913C77.4597 28.0928 77.3696 28.2705 77.2689 28.4461L77.25 28.5402L77.407 28.4086L77.3881 28.5027L77.4635 28.4526C77.455 28.4944 77.4383 28.5237 77.4131 28.5404L77.2748 28.741C77.2204 28.7954 77.1659 28.8497 77.1115 28.904C77.0779 28.9625 77.0339 29.019 76.9794 29.0733C76.9208 29.1485 76.8412 29.2195 76.7407 29.2864C75.9864 30.2226 75.1215 31.0059 74.1458 31.6364C74.1625 31.6616 74.1918 31.6783 74.2336 31.6868L74.1646 31.7055L74.1332 31.6992C74.0914 31.6908 74.0328 31.7116 73.9574 31.7617C73.8862 31.7909 73.8465 31.8264 73.838 31.8683L73.8317 31.8996L73.8191 31.9624L73.7563 31.9497L73.769 31.887L73.5805 32.0123L73.637 32.0563L73.5679 32.075L73.5239 32.1314L73.4738 32.0561L73.3167 32.1877L73.3481 32.194C73.369 32.1982 73.3795 32.2003 73.3795 32.2003C73.4046 32.1836 73.4276 32.1773 73.4485 32.1816L73.4045 32.238L73.4359 32.2443L73.5239 32.1314ZM74.6604 31.6748L74.9556 31.5057C74.9807 31.489 75.0205 31.4535 75.0749 31.3992C75.1545 31.3281 75.2257 31.2989 75.2884 31.3116C75.3093 31.3158 75.3219 31.3074 75.3261 31.2865C75.3512 31.2698 75.3743 31.2636 75.3952 31.2678L75.4015 31.2364L75.3011 31.2488C75.3011 31.2488 75.2906 31.2467 75.2697 31.2425C75.2697 31.2425 75.2718 31.2321 75.276 31.2111C75.3472 31.1819 75.4707 31.1089 75.6466 30.992L75.6402 31.0233L75.4078 31.205L75.4642 31.249L75.816 30.9608C75.8202 30.9399 75.8245 30.919 75.8287 30.8981C75.858 30.8604 75.8978 30.8249 75.948 30.7915C75.948 30.7915 76.0485 30.7247 76.2495 30.5911C76.4129 30.4281 76.4946 30.3466 76.4946 30.3466L76.8967 29.9706L77.0224 29.8327L76.8906 29.8388L77.2237 29.4815L77.2738 29.5569C77.4707 29.3354 77.6425 29.1306 77.7892 28.9425C77.9359 28.7544 78.0679 28.5852 78.1852 28.4347C78.1894 28.4138 78.1811 28.4012 78.1601 28.397C78.1517 28.4388 78.1266 28.4555 78.0848 28.4471L78.1414 28.3279L78.2606 28.3846L78.2231 28.2465L78.2168 28.2778L78.2547 28.0896C78.2295 28.1063 78.2044 28.123 78.1793 28.1397C78.1793 28.1397 78.1772 28.1502 78.173 28.1711L77.777 28.6789L77.0416 29.5754L76.9472 29.7196L76.6771 29.9264L76.0299 30.5469C75.9504 30.6179 75.8729 30.6785 75.7975 30.7286C75.7221 30.7787 75.6572 30.8309 75.6028 30.8852L74.9368 31.4366L74.629 31.6684L74.6604 31.6748ZM76.0868 30.2645C76.1286 30.273 76.1516 30.2667 76.1558 30.2458L76.803 29.6253L76.7904 29.6881L76.9098 29.5815L76.9538 29.5251L76.8597 29.5062L76.7906 29.5249L76.7466 29.5813C76.6586 29.6942 76.4512 29.9136 76.1245 30.2395C76.1245 30.2395 76.1224 30.2499 76.1181 30.2708C76.1181 30.2708 76.1077 30.2687 76.0868 30.2645ZM73.5314 26.2574C73.6406 25.9312 73.7329 25.6886 73.8084 25.5297C73.842 25.4712 73.8922 25.4378 73.9592 25.4295L74.1853 25.2792C74.0346 25.3794 73.9214 25.509 73.8459 25.6679C73.7913 25.831 73.7451 25.9522 73.7074 26.0317C73.6403 26.1487 73.6004 26.2386 73.5878 26.3014L73.5187 26.3201L73.5314 26.2574ZM73.2507 24.8952C73.2716 24.8994 73.2842 24.891 73.2884 24.8701L73.2006 24.8198C73.2006 24.8198 73.1901 24.8177 73.1692 24.8135C73.1692 24.8135 73.1671 24.824 73.1629 24.8449C73.1796 24.87 73.2089 24.8868 73.2507 24.8952ZM73.4707 24.6131C73.4707 24.6131 73.4603 24.611 73.4393 24.6067C73.4393 24.6067 73.4414 24.5963 73.4457 24.5754L73.2383 24.7948L73.2947 24.8388L73.4707 24.6131ZM76.4021 29.0223L76.3771 28.9847C76.3184 29.0599 76.287 29.108 76.2828 29.1289L76.4021 29.0223ZM76.3084 28.6771L76.2771 28.6707L76.0886 28.796C76.0844 28.8169 76.0823 28.8274 76.0823 28.8274C76.1032 28.8316 76.1137 28.8337 76.1137 28.8337L76.3084 28.6771ZM75.8998 29.2476L75.9499 29.323L75.9625 29.2603C76.0128 29.2269 76.0379 29.2102 76.0379 29.2102L76.2013 29.0472L76.4653 28.7086C76.6622 28.4871 76.7753 28.3576 76.8047 28.32L75.7554 29.3165C75.7512 29.3374 75.7491 29.3478 75.7491 29.3478C75.77 29.3521 75.7804 29.3542 75.7804 29.3542L75.8998 29.2476ZM76.6215 29.2297C76.6257 29.2088 76.6174 29.1962 76.5965 29.192L76.4771 29.2986L76.5085 29.3049L76.6215 29.2297ZM73.6215 24.5128C73.6215 24.5128 73.6257 24.4919 73.6341 24.4501L73.565 24.4688C73.5608 24.4898 73.5336 24.5169 73.4833 24.5503C73.5043 24.5545 73.5126 24.5671 73.5084 24.588L73.6215 24.5128ZM73.2959 23.8598L73.3273 23.8661L73.2709 23.8221L72.9947 23.897L73.0197 23.9347L73.2959 23.8598ZM77.0538 29.839C77.1082 29.7847 77.1397 29.7366 77.1481 29.6948C77.1565 29.653 77.1733 29.6237 77.1984 29.607L77.2047 29.5756L77.1734 29.5693C77.1607 29.6321 77.1397 29.6822 77.1104 29.7198C77.0853 29.7366 77.0581 29.7637 77.0287 29.8013C77.0496 29.8055 77.058 29.8181 77.0538 29.839ZM77.3797 30.1658C77.4048 30.1491 77.43 30.1324 77.4551 30.1157C77.4802 30.099 77.4949 30.0801 77.4991 30.0592L77.5871 29.9464C77.5871 29.9464 77.5766 29.9443 77.5557 29.9401C77.5557 29.9401 77.5578 29.9296 77.562 29.9087L77.3546 30.1281C77.3756 30.1323 77.3839 30.1449 77.3797 30.1658ZM76.5508 30.5538C76.7225 30.4578 76.8209 30.4014 76.846 30.3847L76.9654 30.2782L76.9967 30.2845C77.0596 30.1884 77.1853 30.0505 77.3738 29.8708C77.3989 29.8541 77.4157 29.8248 77.4241 29.783L77.5624 29.5824C77.5667 29.5614 77.5667 29.5614 77.5624 29.5824C77.5834 29.5866 77.5959 29.5782 77.6001 29.5573L77.7006 29.5449C77.7048 29.524 77.7111 29.4926 77.7195 29.4508C77.753 29.3922 77.797 29.3358 77.8515 29.2815L78.0338 29.0244L78.0903 29.0684C78.1112 29.0726 78.1467 29.058 78.197 29.0246C78.1427 28.9702 78.1155 28.9429 78.1155 28.9429C78.1155 28.9429 78.1176 28.9325 78.1218 28.9116C78.147 28.8949 78.1616 28.8761 78.1658 28.8551L78.1031 28.8425L78.0338 29.0244L77.9334 29.0368C77.9083 29.0535 77.8915 29.0828 77.8831 29.1246C77.8789 29.1455 77.8642 29.1644 77.8391 29.1811C77.772 29.2981 77.7112 29.3838 77.6568 29.4381C77.3426 29.7013 77.0976 29.9458 76.9216 30.1715L76.5571 30.5224L76.5508 30.5538ZM73.9291 24.4442C73.9333 24.4233 73.9354 24.4128 73.9354 24.4128C73.9563 24.417 73.9667 24.4191 73.9667 24.4191L74.1301 24.2562L74.1364 24.2248C74.0359 24.2916 73.971 24.3438 73.9417 24.3815C73.9417 24.3815 73.9375 24.4024 73.9291 24.4442ZM76.5904 29.0602C76.5695 29.056 76.559 29.0539 76.559 29.0539C76.5632 29.033 76.5653 29.0225 76.5653 29.0225L76.5967 29.0289L76.8167 28.7467L77.1058 28.4459L77.1184 28.3831C77.1435 28.3664 77.1624 28.3267 77.175 28.264L77.307 28.0947C77.2568 28.1281 77.1772 28.1991 77.0683 28.3078C77.0641 28.3287 77.041 28.3349 76.9992 28.3265L76.9428 28.2825C77.0055 28.2951 77.039 28.291 77.0432 28.2701C77.0683 28.2534 77.0851 28.2241 77.0935 28.1823L76.9868 28.2261L76.9428 28.2825L76.5845 28.7653L76.6032 28.8343L76.6346 28.8406C76.6262 28.8825 76.6094 28.9117 76.5843 28.9284L76.4649 29.035L76.4899 29.0727L76.5904 29.0602ZM77.562 29.9087C77.7253 29.8545 77.8091 29.7626 77.8134 29.6329C77.7589 29.6872 77.717 29.7332 77.6877 29.7708C77.6584 29.8084 77.6165 29.8544 77.562 29.9087ZM73.7417 23.7536C73.7083 23.7034 73.6915 23.6783 73.6915 23.6783L73.6162 23.7284C73.6162 23.7284 73.6141 23.7388 73.6099 23.7597C73.6099 23.7597 73.6203 23.7618 73.6412 23.7661L73.7417 23.7536ZM77.789 29.1057L77.6633 29.2436C77.6842 29.2478 77.6925 29.2604 77.6883 29.2813L77.789 29.1057ZM74.0935 23.4654C74.0307 23.4528 73.9763 23.4527 73.9303 23.4652L73.9554 23.5029L74.0935 23.4654ZM74.3257 23.4469L74.332 23.4155L74.1562 23.478L74.3257 23.4469ZM78.0467 28.7985L78.0216 28.7608L77.8959 28.8987L77.9587 28.9114L78.0467 28.7985ZM74.0053 23.7414C74.0387 23.7917 74.0679 23.8084 74.0931 23.7917C74.1182 23.775 74.1433 23.7583 74.1684 23.7416C74.2103 23.75 74.2437 23.7459 74.2689 23.7292C74.294 23.7125 74.3065 23.7041 74.3065 23.7041C74.3399 23.7544 74.3692 23.7712 74.3943 23.7545C74.4237 23.7168 74.4509 23.6897 74.476 23.673L74.5954 23.5664L74.6518 23.6104C74.656 23.5895 74.6581 23.5791 74.6581 23.5791C74.679 23.5833 74.6895 23.5854 74.6895 23.5854C74.8234 23.5688 74.8904 23.5605 74.8904 23.5605C74.9573 23.5523 75.0034 23.5398 75.0285 23.5231C75.0787 23.4897 75.1164 23.4646 75.1415 23.4479L75.2546 23.3727L75.2609 23.3414L75.2295 23.335C75.1626 23.3433 75.0935 23.3621 75.0224 23.3913C74.9721 23.4247 74.9135 23.4455 74.8466 23.4538C74.7838 23.4412 74.7273 23.4516 74.6771 23.485C74.6562 23.4808 74.6353 23.4765 74.6143 23.4723C74.6186 23.4514 74.6081 23.4493 74.583 23.466L74.4449 23.5035L74.3758 23.5222L74.1436 23.5408C74.1227 23.5366 74.0892 23.5407 74.0431 23.5532C73.9971 23.5657 73.9908 23.5971 74.0242 23.6473L73.792 23.6658L73.7857 23.6972C73.8275 23.7056 73.8693 23.714 73.9111 23.7225C73.9572 23.71 73.9886 23.7163 74.0053 23.7414ZM78.2599 28.8741L78.3039 28.8177L78.1848 28.761C78.1848 28.761 78.1827 28.7715 78.1785 28.7924C78.1785 28.7924 78.168 28.7903 78.1471 28.7861L78.1721 28.8238C78.2056 28.874 78.2327 28.9012 78.2536 28.9055L78.2599 28.8741ZM77.1567 27.8686C77.2279 27.8394 77.3179 27.7705 77.4268 27.6618C77.5148 27.549 77.563 27.4716 77.5715 27.4298C77.605 27.3713 77.5988 27.2939 77.5529 27.1976L77.27 27.6302L77.0876 27.8873L77.1567 27.8686ZM77.2262 27.5235C77.2764 27.4901 77.3015 27.4734 77.3015 27.4734L77.2954 27.3416C77.333 27.3709 77.354 27.3751 77.3582 27.3542C77.3833 27.3375 77.4084 27.3208 77.4335 27.3041C77.4126 27.2999 77.4022 27.2978 77.4022 27.2978C77.4064 27.2769 77.4085 27.2664 77.4085 27.2664C77.3582 27.2998 77.3227 27.3144 77.3017 27.3102L77.2954 27.3416C77.2703 27.3583 77.2514 27.398 77.2388 27.4608L77.2262 27.5235ZM77.7401 28.0513L77.8155 28.0012L77.853 28.1393L77.8153 28.1644L77.7401 28.0513ZM77.7597 27.4677C77.8099 27.4343 77.8686 27.359 77.9357 27.242C77.8687 27.2503 77.7934 27.3004 77.7096 27.3923L77.7283 27.4614L77.7597 27.4677ZM78.3229 28.7235C78.3941 28.6944 78.392 28.6504 78.3168 28.5918L78.3795 28.6044C78.4214 28.6128 78.4402 28.6275 78.436 28.6484L78.4926 28.5292L78.4738 28.4602C78.4781 28.4392 78.5011 28.433 78.5429 28.4414C78.5638 28.4456 78.5764 28.4373 78.5806 28.4164C78.6057 28.3997 78.6246 28.3599 78.6372 28.2972C78.6456 28.2554 78.6415 28.2219 78.6248 28.1968C78.7503 28.222 78.788 28.1426 78.7381 27.9584L78.6248 28.1968L78.4425 28.4538L78.4738 28.4602C78.4152 28.5354 78.3628 28.5793 78.3168 28.5918C78.3335 28.6169 78.3355 28.6608 78.3229 28.7235ZM78.6002 27.8327L78.5688 27.8264L78.2608 28.2214L78.3172 28.2654L78.6002 27.8327ZM77.3849 26.0866C77.3599 25.9945 77.3704 25.9422 77.4165 25.9297C77.4667 25.8963 77.5044 25.8712 77.5295 25.8545L77.3849 26.0866ZM78.6065 27.8014C78.6736 27.6843 78.7385 27.5777 78.8014 27.4816C78.7094 27.5065 78.6612 27.5295 78.657 27.5504L78.6317 27.6759C78.6233 27.7177 78.6065 27.747 78.5814 27.7637C78.6023 27.7679 78.6107 27.7805 78.6065 27.8014ZM78.9075 27.9273L79.0082 27.7517L79.1341 27.4506L79.1027 27.4443L78.7694 27.9648L78.7945 28.0024L78.9075 27.9273ZM78.6764 27.13C78.6554 27.1258 78.6471 27.1132 78.6513 27.0923L78.5319 27.1988C78.5528 27.203 78.5612 27.2156 78.557 27.2365L78.6764 27.13ZM78.4441 27.1485C78.4441 27.1485 78.442 27.159 78.4378 27.1799C78.4378 27.1799 78.4483 27.182 78.4692 27.1862L78.5132 27.1298L78.4003 27.0418L78.4694 27.023L78.5008 27.0293L78.5635 27.042C78.5217 27.0335 78.505 27.0084 78.5134 26.9666C78.5218 26.9248 78.5554 26.8662 78.614 26.791L78.5766 26.6529C78.5556 26.6487 78.5326 26.6549 78.5075 26.6716C78.4824 26.6883 78.4677 26.7071 78.4635 26.728L78.3439 26.9978L78.3374 27.1923L78.4441 27.1485ZM76.2273 23.4053C76.29 23.418 76.357 23.4097 76.4281 23.3805C76.4993 23.3513 76.5517 23.3074 76.5852 23.2489C76.5183 23.2572 76.4387 23.2738 76.3467 23.2988C76.2755 23.328 76.2064 23.3467 76.1395 23.355L76.2273 23.4053ZM75.6266 22.0114L75.6329 21.98L75.6079 21.9423L75.4257 22.0362L75.4194 22.0676L75.6266 22.0114ZM78.7147 26.6154C78.7189 26.5945 78.7314 26.5861 78.7524 26.5903L78.6395 26.5023L78.6144 26.4647L78.7025 26.3518C78.7025 26.3518 78.7067 26.3309 78.7151 26.2891L78.6397 26.3392L78.5768 26.4897C78.5683 26.5315 78.5516 26.5608 78.5264 26.5775L78.6896 26.5777L78.7147 26.6154ZM75.8965 21.9678L75.7837 21.8798C75.7627 21.8756 75.7272 21.8902 75.6769 21.9236C75.7103 21.9738 75.727 21.999 75.727 21.999L75.8965 21.9678ZM78.8206 27.2243L78.8456 27.262L78.833 27.3247L78.8644 27.331C78.877 27.2683 78.9127 27.1993 78.9713 27.1241L78.94 27.1177C78.94 27.1177 78.9274 27.1261 78.9023 27.1428C78.8981 27.1637 78.8938 27.1846 78.8896 27.2055C78.8938 27.1846 78.8855 27.1721 78.8646 27.1679C78.9192 27.0048 78.9905 26.8124 79.0787 26.5908C79.1877 26.3733 79.2487 26.1789 79.2614 26.0074L78.6886 27.3936L78.7136 27.4312L78.8206 27.2243ZM78.7151 26.2891C78.7193 26.2682 78.7235 26.2472 78.7277 26.2263C78.7528 26.2096 78.7654 26.2013 78.7654 26.2013C78.7487 26.1761 78.7194 26.1594 78.6776 26.151L78.7151 26.2891ZM79.2537 27.1809L79.2726 27.0868C79.2937 26.9822 79.321 26.9007 79.3545 26.8421L79.3231 26.8358L79.2223 27.1746L79.2473 27.2123L79.2537 27.1809ZM79.1471 27.0615C79.2226 26.9026 79.2688 26.7814 79.2857 26.6977L79.2543 26.6914L79.0844 27.0489L79.1094 27.0866L79.1471 27.0615ZM76.9307 22.992L76.8366 22.9731L76.7989 22.9982C76.8616 23.0108 76.8909 23.0276 76.8867 23.0485L76.9307 22.992ZM78.2083 25.0772L78.2525 24.8576L78.2211 24.8513L78.1898 24.845L78.1771 24.9077C78.1645 24.9705 78.1665 25.0144 78.1832 25.0395L78.1706 25.1023L78.2083 25.0772ZM79.4741 26.5724L79.493 26.4783L79.4617 26.472L79.4113 26.5598L79.4301 26.6289L79.4741 26.5724ZM75.9342 21.9427C76.0263 21.9177 76.0974 21.8886 76.1477 21.8551C76.1937 21.8427 76.2397 21.8302 76.2858 21.8177C76.3318 21.8052 76.3862 21.8052 76.449 21.8179C76.4699 21.8221 76.5012 21.8284 76.5431 21.8368C76.5891 21.8243 76.6163 21.7972 76.6248 21.7553L76.7441 21.6488C76.765 21.653 76.7776 21.6447 76.7818 21.6237C76.8027 21.628 76.8132 21.6301 76.8132 21.6301C76.8174 21.6091 76.8195 21.5987 76.8195 21.5987L76.7881 21.5924C76.7421 21.6049 76.6856 21.6153 76.6186 21.6235C76.5768 21.6151 76.5391 21.6402 76.5056 21.6987C76.472 21.7572 76.3779 21.7927 76.223 21.805L75.8527 21.861C75.8861 21.9113 75.9133 21.9385 75.9342 21.9427ZM78.9168 25.6115C78.9294 25.5488 78.9462 25.5195 78.9671 25.5237L78.9797 25.461C78.9839 25.4401 78.9756 25.4275 78.9547 25.4233L78.873 25.5048C78.8688 25.5257 78.8834 25.5613 78.9168 25.6115ZM79.4993 26.447C79.5203 26.4512 79.5328 26.4428 79.537 26.4219L79.6189 26.1773C79.5771 26.1688 79.5373 26.2043 79.4996 26.2838C79.466 26.3423 79.4555 26.3946 79.468 26.4406L79.4993 26.447ZM77.3135 23.0365C77.3428 22.9988 77.3659 22.9382 77.3827 22.8546L77.3513 22.8482L77.2507 23.0238L77.3135 23.0365ZM77.1067 22.7663C77.1067 22.7663 77.1276 22.7706 77.1694 22.779L77.2699 22.7666C77.295 22.7498 77.3285 22.7457 77.3703 22.7541L77.3829 22.6914L77.1193 22.7036L77.113 22.735C77.0879 22.7517 77.0753 22.76 77.0753 22.76C77.0962 22.7642 77.1067 22.7663 77.1067 22.7663ZM79.0475 26.4213C79.1399 26.1787 79.2238 25.978 79.2993 25.8191L79.2677 25.976L79.2991 25.9823L79.4376 25.6185C79.3958 25.6101 79.3623 25.6142 79.3372 25.6309L79.3435 25.5995C79.4314 25.5955 79.4649 25.5369 79.4442 25.4239C79.4484 25.403 79.4421 25.38 79.4254 25.3549C79.4087 25.3298 79.392 25.3046 79.3753 25.2795C79.3922 25.1959 79.3943 25.131 79.3818 25.085L79.0162 26.415L79.0475 26.4213ZM77.0002 22.647C77.0253 22.6303 77.1069 22.6032 77.245 22.5657C77.2701 22.549 77.312 22.5574 77.3705 22.591C77.4542 22.6078 77.5211 22.5995 77.5714 22.5661C77.6968 22.5914 77.7366 22.5559 77.6907 22.4596C77.6698 22.4554 77.6384 22.449 77.5966 22.4406C77.5799 22.4155 77.559 22.4113 77.5339 22.428C77.2033 22.4485 76.9941 22.4608 76.9063 22.4649L76.8749 22.4585L76.8686 22.4899C76.8853 22.515 76.9041 22.5297 76.925 22.5339C76.9668 22.5423 76.9856 22.557 76.9814 22.5779L76.9877 22.5465C76.9626 22.5632 76.9458 22.5925 76.9374 22.6343L77.0002 22.647ZM78.9296 25.3856C78.9799 25.3522 79.005 25.3355 79.005 25.3355C79.0343 25.2979 79.0427 25.2561 79.0302 25.21C79.0387 25.1682 79.0575 25.1285 79.0869 25.0909C79.0953 25.049 79.0954 24.9947 79.0871 24.9277C79.083 24.8398 79.1061 24.7792 79.1563 24.7458L79.0875 24.6014L79.0561 24.5951C78.9389 24.6367 78.9137 24.7078 78.9805 24.8083L79.0054 25.0092L78.9614 25.0656L78.9109 25.3166L78.9296 25.3856ZM77.1583 21.6995L77.1709 21.6368L76.8382 21.6677L76.857 21.7368L77.1583 21.6995ZM78.1165 23.2634C78.2671 23.272 78.424 23.2492 78.5872 23.195L78.4681 23.1383L78.5121 23.0819L78.3929 23.0253C78.3929 23.0253 78.3845 23.0127 78.3678 22.9876C78.372 22.9667 78.3637 22.9541 78.3428 22.9499C78.3219 22.9457 78.2696 22.9352 78.1859 22.9183C78.1023 22.9015 78.0353 22.9098 77.9851 22.9432C78.0019 22.8595 77.9685 22.8093 77.8849 22.7924C77.8221 22.7798 77.7719 22.7588 77.7343 22.7295L77.8661 22.7234C77.8118 22.6689 77.7407 22.6437 77.6528 22.6478C77.5692 22.631 77.5022 22.6392 77.452 22.6726C77.4436 22.7145 77.4498 22.7375 77.4707 22.7417L77.5962 22.767C77.6129 22.7921 77.6526 22.811 77.7154 22.8236L77.6524 22.9741L77.5962 22.767L77.4642 22.9362C77.46 22.9572 77.4328 22.9843 77.3825 23.0177L77.3762 23.0491L77.4453 23.0304C77.4954 23.1057 77.5434 23.1372 77.5895 23.1247C77.7777 23.1626 77.9157 23.1795 78.0036 23.1754L78.1228 23.232L78.1165 23.2634ZM78.092 22.7362L77.9979 22.7173L78.0731 22.8303L78.092 22.7362ZM79.7014 25.4431C79.7224 25.4473 79.7349 25.439 79.7391 25.418L79.7457 25.2235L79.7143 25.2172L79.7014 25.4431ZM77.2524 21.7185C77.3151 21.7311 77.3716 21.7207 77.4219 21.6873L77.4282 21.6559L77.2524 21.7185ZM77.3907 21.5178L77.3343 21.4738L77.2399 21.6181L77.265 21.6557L77.3907 21.5178ZM79.4515 24.5767L79.433 24.3445C79.4288 24.3654 79.4162 24.3738 79.3953 24.3696L79.3888 24.5641L79.4515 24.5767ZM77.7398 38.4641L77.7275 38.2005C77.7444 38.1168 77.734 38.0603 77.6964 38.031L77.709 37.9682L77.7722 37.6545C77.8393 37.5375 77.8791 37.4476 77.8918 37.3848C77.9002 37.343 77.8772 37.2948 77.8229 37.2404C77.802 37.2362 77.7832 37.2215 77.7665 37.1964C77.7707 37.1755 77.7749 37.1546 77.7791 37.1336L77.7917 37.0709C77.8044 37.0082 77.8379 36.9496 77.8924 36.8953C77.9426 36.8619 77.9824 36.8264 78.0118 36.7888C78.0453 36.7302 78.1647 36.5693 78.3701 36.306C78.4874 36.1555 78.5671 36.0301 78.609 35.9298L78.6404 35.9361L78.7095 35.9173C78.7179 35.8755 78.7514 35.817 78.8101 35.7417L79.1497 35.1899L79.156 35.1585C79.2063 35.1251 79.2335 35.098 79.2377 35.0771C79.267 35.0394 79.2838 35.0102 79.288 34.9893L79.483 34.6695L79.5962 34.4311L79.6025 34.3998C79.6025 34.3998 79.5921 34.3976 79.5712 34.3934C79.5712 34.3934 79.5691 34.4039 79.5649 34.4248L79.3889 34.6505C79.3889 34.6505 79.3784 34.6484 79.3575 34.6442C79.3575 34.6442 79.3554 34.6546 79.3512 34.6756L79.3575 34.6442L79.3701 34.5815L79.3324 34.6065L79.3011 34.6002L79.3074 34.5688L79.4834 34.3431L79.7097 34.0296C79.7684 33.9544 79.7998 33.9063 79.804 33.8854L80.068 33.5468L80.0556 33.4464L79.9802 33.4965L79.8985 33.578L79.9175 33.4839L79.9238 33.4525L79.9175 33.4839C79.7792 33.6302 79.6954 33.7221 79.6661 33.7597C79.6159 33.7931 79.5488 33.8558 79.4651 33.9477C79.3855 34.0187 79.3268 34.094 79.289 34.1734L79.2137 34.2235L79.2263 34.1608C79.3227 34.0061 79.3835 33.9204 79.4086 33.9037C79.4966 33.7909 79.5616 33.6843 79.6036 33.5839C79.6665 33.4878 79.7272 33.4021 79.7859 33.3268C79.8446 33.2516 79.8781 33.1931 79.8865 33.1512L79.8929 33.1199L79.8865 33.1512L79.8552 33.1449L79.8112 33.2014L79.8238 33.1386L79.8364 33.0759L79.8427 33.0445C79.8218 33.0403 79.8093 33.0486 79.8051 33.0696C79.7841 33.0653 79.7716 33.0737 79.7674 33.0946L79.78 33.0319L79.843 32.8813C79.8472 32.8604 79.8388 32.8479 79.8179 32.8436C79.8179 32.8436 79.8074 32.8415 79.7865 32.8373C79.7865 32.8373 79.7844 32.8478 79.7802 32.8687C79.7258 32.923 79.665 33.0087 79.5979 33.1258L79.3402 33.433L78.9442 33.9408L78.1081 35.0129C78.0286 35.0839 77.9699 35.1591 77.9321 35.2386C77.8986 35.2971 77.8672 35.3452 77.8378 35.3828C77.7876 35.4162 77.7582 35.4538 77.7498 35.4956L77.4355 35.922C77.4104 35.9387 77.3936 35.968 77.3852 36.0098L77.3538 36.0035C77.3538 36.0035 77.3433 36.0014 77.3224 35.9972C77.3266 35.9762 77.3392 35.9679 77.3601 35.9721C77.5278 35.6795 77.641 35.4955 77.6997 35.4203L78.3787 34.4798L79.1017 33.4829L79.1206 33.3887L79.0766 33.4452L78.9949 33.5267L78.6052 34.0031C78.5717 34.0616 78.4522 34.2226 78.2469 34.4859L78.2532 34.4545L78.3915 34.2539L78.4481 34.1347L78.4545 34.1033C78.4126 34.0949 78.4022 34.0928 78.4231 34.097C78.4482 34.0803 78.4629 34.0615 78.4671 34.0406L78.5176 33.7896L78.2789 34.0027C78.258 33.9985 78.2433 34.0173 78.2349 34.0591C78.2182 34.034 78.214 34.0005 78.2224 33.9587C78.2309 33.9169 78.2644 33.8583 78.3231 33.7831L78.606 33.3504C78.6354 33.3128 78.6585 33.2522 78.6753 33.1685L78.8073 32.9993L78.8136 32.9679L78.7823 32.9616L78.5686 33.2123L78.4995 33.2311C78.5037 33.2102 78.4849 33.1955 78.4431 33.1871C78.4264 33.1619 78.4306 33.141 78.4557 33.1243L78.7197 32.7858L79.3547 31.9017L79.5747 31.6196L79.5873 31.5568L79.5183 31.5756L79.38 31.7762C79.3757 31.7971 79.3632 31.8055 79.3423 31.8013L79.3486 31.7699L79.3612 31.7072L79.3298 31.7008C79.2712 31.7761 79.2167 31.8304 79.1665 31.8638L79.1728 31.8324L79.3551 31.5754C79.3844 31.5377 79.4473 31.4416 79.5437 31.2869L79.9147 30.7414L80.4743 29.9074C80.6503 29.6817 80.7719 29.5104 80.8389 29.3933L81.3796 28.6534L81.8575 27.901L82.4422 27.1047L83.2407 25.8945L83.6746 25.1984L84.5738 23.8127C84.8002 23.4448 84.9993 23.1584 85.1711 22.9536C85.2256 22.8993 85.3701 22.7217 85.6048 22.4208L85.8562 22.1449L86.1202 21.8064C86.2124 21.6726 86.3338 21.61 86.4844 21.6186C86.5053 21.6228 86.5388 21.6186 86.5849 21.6062C86.6351 21.5727 86.6811 21.5603 86.723 21.5687C86.836 21.5479 86.9113 21.5522 86.9489 21.5815C86.9698 21.5857 86.9991 21.6025 87.0367 21.6318C87.0785 21.6403 87.1329 21.6403 87.1998 21.632C87.2501 21.5986 87.2898 21.6175 87.319 21.6887C87.3775 21.7222 87.4403 21.7348 87.5072 21.7266L87.7331 21.7394C87.8168 21.7562 87.8795 21.8233 87.9212 21.9405L87.9776 21.9845C88.0235 22.0808 88.0883 22.1373 88.1719 22.1542C88.2807 22.1543 88.356 22.1586 88.3978 22.167C88.5776 22.2467 88.7009 22.3368 88.7678 22.4373C88.9098 22.5965 89.0267 22.7724 89.1185 22.9649C89.2187 23.1157 89.2689 23.191 89.2689 23.191C89.2856 23.2162 89.3399 23.2706 89.4318 23.3544C89.4652 23.4047 89.4819 23.4298 89.4819 23.4298L89.6009 23.6496C89.6844 23.7752 89.6613 23.8359 89.5316 23.8315C89.4438 23.8356 89.3579 23.8836 89.2741 23.9755C89.2155 24.0508 89.1464 24.0695 89.067 24.0317C88.9624 24.0107 88.8933 24.0294 88.8598 24.088C88.8556 24.1089 88.8326 24.1151 88.7907 24.1067L88.6716 24.0501C88.6088 24.0374 88.5691 24.0186 88.5524 23.9934C88.473 23.9557 88.406 23.964 88.3515 24.0183C88.1254 24.1686 87.9369 24.3483 87.786 24.5573C87.7023 24.6492 87.6017 24.7704 87.4843 24.9209C87.3712 25.0504 87.2518 25.2114 87.126 25.4037L86.4974 26.2564L86.0258 26.9775L85.6108 27.5794C85.5857 27.5961 85.5417 27.6525 85.4788 27.7487C85.4368 27.849 85.3677 27.9222 85.2714 27.9681C85.2463 27.9848 85.2274 28.0245 85.2148 28.0872C85.131 28.1792 85.0765 28.2335 85.0514 28.2502C85.0012 28.2836 84.9174 28.3755 84.8 28.526L84.3977 29.0652L84.0394 29.548L83.6307 30.1186L83.2724 30.6013C83.1006 30.8061 82.8638 31.1175 82.5621 31.5355L81.99 32.269L81.55 32.8333L81.1854 33.3474C81.1476 33.4269 81.0952 33.5251 81.0281 33.6422C80.961 33.7593 80.8688 33.893 80.7515 34.0435C80.7137 34.1229 80.6529 34.2086 80.5691 34.3006C80.5105 34.3758 80.4476 34.472 80.3805 34.589L79.8335 35.3602L79.6198 35.611L79.5569 35.7615L79.4122 35.9935L79.2866 36.1314L79.2802 36.1628C79.2049 36.2129 79.1232 36.2944 79.0352 36.4073C78.9472 36.5201 78.8759 36.6037 78.8215 36.658L78.6015 36.9401C78.4339 37.124 78.3165 37.3289 78.2493 37.5547L78.268 37.6238C78.3265 37.6573 78.3307 37.6908 78.2804 37.7242C78.1966 37.8161 78.1442 37.9144 78.1231 38.019C78.0812 38.1193 77.9932 38.2322 77.8591 38.3575C77.8465 38.4203 77.8276 38.46 77.8025 38.4767L77.7585 38.5331L77.7398 38.4641ZM77.6917 36.757L77.698 36.7256L77.742 36.6692L77.7608 36.7383L77.7545 36.7696L77.6728 36.8511L77.6917 36.757ZM78.1118 37.1027L78.137 36.9772L78.1497 36.9145L78.1623 36.8517L78.1183 36.9082C78.089 36.9458 78.0659 37.0064 78.049 37.0901L78.0678 37.1591L78.1118 37.1027ZM78.1745 37.1153C78.1703 37.1362 78.1786 37.1488 78.1996 37.153C78.2205 37.1572 78.233 37.1489 78.2372 37.128C78.2791 37.1364 78.3042 37.1197 78.3126 37.0778C78.3168 37.0569 78.3064 37.0004 78.2815 36.9084L78.1935 37.0212L78.1558 37.0463C78.1473 37.0881 78.1536 37.1111 78.1745 37.1153ZM77.9806 36.6193C78.0477 36.5022 78.1127 36.3956 78.1755 36.2995L78.2132 36.2744C78.209 36.2953 78.2069 36.3058 78.2069 36.3058C78.2236 36.3309 78.2194 36.3518 78.1943 36.3685C78.1692 36.3852 78.1524 36.4145 78.144 36.4563C78.1313 36.5191 78.1103 36.5693 78.081 36.6069C78.0726 36.6487 78.039 36.7072 77.9804 36.7825L77.949 36.7761L77.9806 36.6193ZM78.457 37.009C78.478 37.0132 78.4905 37.0049 78.4947 36.9839L78.5954 36.8083C78.6038 36.7665 78.6185 36.7477 78.6394 36.7519L78.6143 36.7142L78.5326 36.7957L78.5263 36.8271C78.5137 36.8898 78.4927 36.94 78.4634 36.9776L78.457 37.009ZM77.9119 36.3117C77.9204 36.2699 77.9413 36.2197 77.9749 36.1612C78.0336 36.0859 78.0776 36.0295 78.1069 35.9919L78.3899 35.5592C78.4192 35.5216 78.4423 35.461 78.4591 35.3773L78.4968 35.3523L78.4905 35.3836C78.4863 35.4045 78.4842 35.415 78.4842 35.415C78.5051 35.4192 78.5155 35.4213 78.5155 35.4213C78.5574 35.4297 78.5636 35.4528 78.5343 35.4904L78.3143 35.7725C78.2934 35.7683 78.2808 35.7766 78.2766 35.7976L78.2953 35.8666C78.2995 35.8457 78.3121 35.8373 78.333 35.8416L78.3456 35.7788C78.3666 35.783 78.3749 35.7956 78.3707 35.8165C78.3623 35.8583 78.3455 35.8876 78.3204 35.9043L78.1507 36.0986L78.1381 36.1614C78.1381 36.1614 78.136 36.1718 78.1317 36.1927C78.1275 36.2137 78.138 36.2158 78.1631 36.1991L78.1568 36.2304L77.9747 36.3243C77.9705 36.3452 77.9579 36.3536 77.937 36.3494L77.8993 36.3744L77.9119 36.3117ZM78.6598 35.5156L78.5151 35.7476L78.4838 35.7413L78.6598 35.5156ZM78.9097 36.382C78.9306 36.3862 78.9432 36.3779 78.9474 36.3569L79.1674 36.0748L79.136 36.0685L78.8846 36.3443C78.9056 36.3485 78.9139 36.3611 78.9097 36.382ZM78.6156 35.7352C78.6198 35.7143 78.6114 35.7017 78.5905 35.6975L78.8105 35.4154C78.8314 35.4196 78.844 35.4113 78.8482 35.3904L78.8419 35.4217L78.6219 35.7039L78.6156 35.7352ZM78.8044 35.2836L78.8107 35.2522C78.8065 35.2732 78.8044 35.2836 78.8044 35.2836C78.8253 35.2878 78.8358 35.2899 78.8358 35.2899L78.6598 35.5156L78.8044 35.2836ZM78.8238 34.8632C78.8322 34.8213 78.849 34.7921 78.8741 34.7754L78.9871 34.7002L78.9808 34.7316L78.9368 34.788L78.8551 34.8695L78.8488 34.9009L78.8238 34.8632ZM78.905 35.108C78.9302 35.0913 78.9469 35.0621 78.9554 35.0202L79.0874 34.8509L79.1627 34.8008L79.1438 34.895L78.9301 35.1457L78.8987 35.1394L78.905 35.108ZM79.044 34.4179C79.0482 34.397 79.0754 34.3698 79.1257 34.3364C79.1299 34.3155 79.1424 34.3071 79.1634 34.3113L79.157 34.3427L79.0754 34.4242C79.0711 34.4451 79.0586 34.4534 79.0377 34.4492L79.044 34.4179ZM79.6402 34.3747C79.6444 34.3538 79.6465 34.3433 79.6465 34.3433C79.6675 34.3475 79.6779 34.3496 79.6779 34.3496L79.8162 34.149L79.8226 34.1176C79.8226 34.1176 79.8121 34.1155 79.7912 34.1113C79.7912 34.1113 79.7891 34.1218 79.7849 34.1427L79.6592 34.2806L79.6402 34.3747ZM79.4657 33.4582C79.4908 33.4415 79.5055 33.4227 79.5097 33.4018C79.5181 33.36 79.5349 33.3307 79.56 33.314L79.5977 33.2889L79.585 33.3517L79.497 33.4645C79.497 33.4645 79.4866 33.4624 79.4657 33.4582C79.4657 33.4582 79.4636 33.4687 79.4594 33.4896L79.4657 33.4582ZM80.1624 33.4026C80.1875 33.3859 80.2064 33.3462 80.219 33.2835C80.1687 33.3169 80.1415 33.344 80.1373 33.3649L80.131 33.3963L80.1624 33.4026ZM81.7635 32.7457L81.9206 32.6141L81.9142 32.6455L81.7949 32.752C81.7907 32.7729 81.7781 32.7813 81.7572 32.7771L81.7635 32.7457ZM84.4809 39.1683C84.3722 39.0594 84.274 39.007 84.1861 39.0111C84.1191 39.0194 84.0669 39.0088 84.0292 38.9795C83.9874 38.9711 83.9456 38.9627 83.9038 38.9542C83.7783 38.929 83.7009 38.8808 83.6717 38.8096C83.6508 38.8054 83.6341 38.7803 83.6216 38.7342C83.584 38.7049 83.5422 38.6965 83.4962 38.709C83.4627 38.6587 83.4189 38.6064 83.3646 38.5519C83.2851 38.5141 83.2391 38.4723 83.2267 38.4262C83.2309 38.4053 83.233 38.3948 83.233 38.3948C83.2121 38.3906 83.2016 38.3885 83.2016 38.3885C83.0803 38.3424 82.9821 38.2355 82.9071 38.0681L82.7694 37.7792L82.6003 37.4841L82.6255 37.3586C82.6422 37.3837 82.6632 37.3879 82.6883 37.3712C82.6883 37.3712 82.6862 37.3817 82.682 37.4026L82.914 37.5472L82.9454 37.5535C82.9454 37.5535 82.9475 37.5431 82.9517 37.5222C82.9517 37.5222 82.9412 37.5201 82.9203 37.5158L82.6695 37.3022L82.6759 37.2708C82.7177 37.2792 82.7407 37.273 82.7449 37.252C82.7491 37.2311 82.7408 37.2186 82.7199 37.2144C82.6865 37.1641 82.6949 37.1223 82.7451 37.0889C82.7745 37.0513 82.7912 37.022 82.7954 37.0011L82.8331 36.976C82.854 36.9802 82.8854 36.9865 82.9272 36.995C82.9691 37.0034 82.9962 37.0306 83.0087 37.0767C83.0045 37.0976 83.0129 37.1101 83.0338 37.1143L83.0401 37.083C83.0067 37.0327 82.9795 37.0055 82.9586 37.0013C82.9377 36.9971 82.9168 36.9929 82.8959 36.9887C82.8792 36.9635 82.8855 36.9322 82.9148 36.8945L82.9211 36.8632C82.8835 36.8338 82.871 36.7878 82.8837 36.7251C82.8963 36.6623 82.9152 36.6226 82.9403 36.6059C82.9821 36.6143 83.0051 36.6081 83.0093 36.5872C83.0178 36.5453 83.0262 36.5035 83.0346 36.4617C83.0263 36.3947 83.0368 36.3424 83.0662 36.3048L83.3053 35.7654C83.3096 35.7445 83.3892 35.6191 83.5443 35.3892L83.8022 34.9188L84.1669 34.4047L84.6258 33.7463L84.9338 33.3513C84.9674 33.2928 85.0009 33.2343 85.0345 33.1757C85.0722 33.0963 85.1204 33.0189 85.1791 32.9437L85.2985 32.8372L85.6568 32.3544L85.8391 32.0973C85.8937 31.9342 85.9923 31.7691 86.1347 31.6019C86.2563 31.4305 86.3485 31.2968 86.4114 31.2006L86.5434 31.0314C86.6691 30.8391 86.7739 30.6969 86.8577 30.605C87.017 30.3542 87.1679 30.1452 87.3103 29.978C87.3941 29.8861 87.4591 29.7795 87.5053 29.6582C87.5892 29.4575 87.6878 29.2923 87.8009 29.1628C87.8805 29.0918 87.9664 28.9894 88.0586 28.8556C88.1508 28.7218 88.2262 28.6173 88.2849 28.5421L88.5552 28.1722C88.681 27.9799 88.7858 27.8378 88.8696 27.7458C88.9869 27.5954 89.0854 27.4846 89.1649 27.4136L89.1713 27.3822L89.3913 27.1001L89.561 26.9058C89.5987 26.8263 89.672 26.7323 89.781 26.6236C89.8396 26.5484 89.8878 26.4711 89.9256 26.3916C89.9843 26.3164 90.0555 26.2328 90.1393 26.1409C90.3069 25.957 90.4221 25.817 90.485 25.7208C90.8873 25.236 91.1785 24.8703 91.3587 24.6237C91.6436 24.2893 91.849 24.026 91.9747 23.8337C92.1423 23.6499 92.2597 23.4994 92.3267 23.3823C92.4734 23.1942 92.5657 23.0061 92.6036 22.8179C92.6162 22.7551 92.6561 22.6652 92.7232 22.5482C92.7651 22.4478 92.8615 22.3475 93.0122 22.2473L93.3704 21.9277C93.45 21.8567 93.586 21.7752 93.7786 21.6834C93.9042 21.5999 94.1281 21.5688 94.4502 21.5902C94.6175 21.6238 94.7409 21.6596 94.8204 21.6973C94.858 21.7267 94.8977 21.7455 94.9395 21.754C95.0065 21.7457 95.0588 21.7562 95.0964 21.7855C95.4853 21.9074 95.7633 22.0939 95.9303 22.3451L96.1245 22.678L96.231 22.7974L96.2497 22.8664C96.2246 22.8831 96.1596 23.0441 96.0546 23.3494L95.9853 23.5313L95.9224 23.6819C95.8971 23.8073 95.9765 23.8995 96.1605 23.9583C96.2441 23.9751 96.3027 24.0087 96.3361 24.0589L96.3298 24.0903L96.2984 24.084L96.1102 24.0461C96.0181 24.0711 95.9574 24.1024 95.9281 24.14L95.639 24.4409C95.639 24.4409 95.6369 24.4513 95.6327 24.4722C95.6327 24.4722 95.6222 24.4701 95.6013 24.4659C95.4841 24.5076 95.4338 24.5954 95.4503 24.7293L95.4 24.8171C95.3958 24.838 95.3686 24.8652 95.3183 24.8986C95.3057 24.9613 95.2889 24.9906 95.268 24.9864C95.2429 25.0031 95.222 24.9989 95.2053 24.9737C95.1886 24.9486 95.1698 24.9339 95.1489 24.9297C95.0861 24.9171 95.0296 24.9275 94.9794 24.9609L94.6086 25.3432C94.441 25.5271 94.3342 25.6797 94.288 25.801C94.2459 26.0101 94.1033 26.2317 93.8604 26.4657L93.345 27.08L93.0119 27.4373L92.9302 27.5188C92.926 27.5397 92.8946 27.5878 92.8359 27.663C92.8066 27.7006 92.7626 27.7571 92.7039 27.8323C92.6495 27.8866 92.5929 27.9514 92.5342 28.0266C92.4085 28.2189 92.3037 28.361 92.2199 28.453C92.1361 28.5449 92.0481 28.6578 91.9559 28.7915C91.8846 28.9295 91.8301 29.0382 91.7923 29.1177L91.4967 29.6131L91.5281 29.6194L91.7291 29.4314C91.9679 29.2183 92.0873 29.1118 92.0873 29.1118C92.2883 28.9781 92.5916 28.9304 92.9974 28.9686C93.1647 29.0023 93.2923 29.0171 93.3802 29.013L93.4116 29.0193L93.4994 29.0696C93.4742 29.0863 93.4408 29.0905 93.3989 29.082L92.8781 29.0751C92.5768 29.058 92.3236 29.1267 92.1184 29.2812C91.9677 29.3815 91.8441 29.5089 91.7477 29.6636C91.559 29.952 91.3663 30.1526 91.1695 30.2653C91.1695 30.2653 91.0314 30.3572 90.755 30.5409C90.6042 30.6411 90.4304 30.802 90.2335 31.0235C90.0659 31.2074 89.9486 31.3578 89.8815 31.4749C89.6468 31.7758 89.4813 32.0036 89.3848 32.1583C89.3262 32.2336 89.2549 32.3171 89.1711 32.4091C89.1125 32.4843 89.0391 32.5784 88.9511 32.6912C88.8967 32.7455 88.838 32.8208 88.7751 32.9169C88.7122 33.0131 88.6557 33.0778 88.6054 33.1112C88.4965 33.2199 88.3498 33.408 88.1654 33.6755C88.1654 33.6755 88.1403 33.6922 88.09 33.7256C88.0816 33.7674 88.0523 33.805 88.002 33.8385L87.7631 34.2147L87.4738 34.6787L87.3481 34.8166L87.2601 34.9295C87.2517 34.9713 87.2558 35.0048 87.2725 35.0299C87.2767 35.009 87.2893 35.0006 87.3102 35.0049C87.3311 35.0091 87.3437 35.0007 87.3479 34.9798L87.6307 34.7103C87.6307 34.7103 87.6558 34.6936 87.706 34.6602L87.6871 34.7543L87.2597 35.2558L86.8511 35.8264C86.8175 35.8849 86.807 35.9372 86.8195 35.9832C86.8362 36.0084 86.878 36.0168 86.945 36.0085C87.0077 36.0211 87.0725 36.0233 87.1395 36.015C87.2064 36.0068 87.2713 36.0089 87.334 36.0216C87.4428 36.0217 87.5746 36.0156 87.7294 36.0032C87.8885 35.97 88.0224 35.9534 88.1311 35.9535L88.4764 35.8598L88.6585 35.7659L88.7276 35.7472C88.8531 35.7725 88.9326 35.7558 88.9661 35.6973C88.9703 35.6764 88.9725 35.6659 88.9725 35.6659C88.9934 35.6701 89.0038 35.6722 89.0038 35.6722L88.9975 35.7036L88.8404 35.8352C88.7902 35.8686 88.786 35.8895 88.8278 35.8979C88.8487 35.9022 88.855 35.9252 88.8466 35.967C88.8633 35.9921 88.8842 35.9963 88.9093 35.9796L89.2796 35.9236L89.311 35.9299C89.3319 35.9341 89.3528 35.9384 89.3737 35.9426C89.3989 35.9259 89.4052 35.8945 89.3927 35.8485L89.4367 35.792L89.5058 35.7733C89.5685 35.7859 89.5873 35.8006 89.5622 35.8173L89.5872 35.855L89.6249 35.8299C89.6124 35.7839 89.6397 35.7567 89.7066 35.7484L89.9765 35.7049L90.102 35.7301C90.102 35.7301 90.1104 35.7427 90.1271 35.7678C90.1689 35.7762 90.194 35.7595 90.2024 35.7177L90.2401 35.6926C90.2568 35.7178 90.2861 35.7345 90.3279 35.743C90.3739 35.7305 90.4053 35.7368 90.422 35.7619L90.4911 35.7432C90.5664 35.6931 90.6041 35.668 90.6041 35.668C90.6293 35.6513 90.6523 35.645 90.6732 35.6493C90.715 35.6577 90.7485 35.6535 90.7736 35.6368C90.8112 35.6662 90.8552 35.6641 90.9054 35.6307C90.9557 35.5973 90.9912 35.5827 91.0122 35.5869C91.054 35.5954 91.1 35.5829 91.1503 35.5495L91.2631 35.6375L91.2254 35.6625C91.1669 35.629 91.1062 35.6603 91.0433 35.7564C91.0224 35.7522 91.0098 35.7606 91.0056 35.7815C91.0266 35.7857 91.037 35.7878 91.037 35.7878L91.0997 35.8004C91.1542 35.7461 91.2002 35.7336 91.2379 35.7629L91.3069 35.7442C91.332 35.7275 91.3572 35.7108 91.3823 35.6941C91.4283 35.6816 91.4848 35.6712 91.5518 35.6629C91.5727 35.6671 91.581 35.6797 91.5768 35.7006L91.6019 35.7383C91.627 35.7216 91.6584 35.7279 91.696 35.7572C91.7378 35.7657 91.7734 35.7511 91.8027 35.7135L91.8718 35.6947C92.0224 35.7033 92.1647 35.6993 92.2986 35.6827C92.4325 35.6661 92.5433 35.6558 92.6312 35.6517L92.8321 35.6269C92.8572 35.6102 92.8781 35.6144 92.8948 35.6395C92.9366 35.648 92.9638 35.6752 92.9763 35.7212L92.995 35.7903L93.0201 35.828L92.9698 35.9158L92.5742 36.0973L92.4548 36.2038C92.4255 36.2414 92.4317 36.2644 92.4735 36.2728L92.4986 36.3105C92.4986 36.3105 92.4965 36.321 92.4923 36.3419C92.4923 36.3419 92.4818 36.3398 92.4609 36.3356L92.1093 36.4607C91.9252 36.5106 91.7849 36.5586 91.6886 36.6045C91.6217 36.6127 91.538 36.6503 91.4375 36.7171L91.4312 36.7485L91.4625 36.7548L91.7701 36.6861L91.8015 36.6925C91.7555 36.705 91.7094 36.7174 91.6634 36.7299C91.6173 36.7424 91.5692 36.7654 91.519 36.7988C91.519 36.7988 91.4687 36.8322 91.3682 36.899L91.2552 36.9742L91.117 37.0117L91.1044 37.0744L91.1671 37.087L91.4371 37.0434L91.732 37.0375C91.958 36.996 92.1358 36.9774 92.2655 36.9817C92.2571 37.0236 92.2403 37.0528 92.2152 37.0695C92.2152 37.0695 92.2048 37.0674 92.1838 37.0632C92.1881 37.0423 92.1881 37.0423 92.1838 37.0632L92.1525 37.0569C92.1859 37.1071 92.1712 37.126 92.1085 37.1133L92.0771 37.107L91.9767 37.1194L91.9891 37.2199C91.9849 37.2408 91.9828 37.2512 91.9828 37.2512C92.0037 37.2554 92.0142 37.2575 92.0142 37.2575L92.4409 37.2455L92.4723 37.2519L92.5413 37.2331L92.4973 37.2895L92.4847 37.3523L92.6666 37.4215C92.7127 37.4091 92.7482 37.3945 92.7734 37.3778C92.8194 37.3653 92.8738 37.3653 92.9365 37.378C93.0202 37.3948 93.085 37.397 93.1311 37.3845L93.1624 37.3908L93.1561 37.4222L93.1248 37.4159L93.0494 37.466L93.1999 37.5289L93.4195 37.5731C93.4404 37.5773 93.4488 37.5899 93.4446 37.6108C93.5114 37.7113 93.5448 37.7616 93.5448 37.7616L93.5385 37.7929L93.5071 37.7866C93.5113 37.7657 93.503 37.7531 93.482 37.7489C93.4486 37.6987 93.4089 37.6798 93.3629 37.6923C93.3168 37.7048 93.2834 37.7089 93.2625 37.7047L93.2185 37.7611L93.2812 37.7738C93.3439 37.7864 93.3878 37.8388 93.4128 37.9308C93.4128 37.9308 93.4107 37.9413 93.4065 37.9622C93.4274 37.9664 93.4504 37.9602 93.4755 37.9435L93.6324 37.975C93.6366 37.9541 93.6366 37.9541 93.6324 37.975C93.6533 37.9792 93.6637 37.9814 93.6637 37.9814L93.6324 37.975C93.5403 38 93.4649 38.0501 93.4063 38.1254L93.3372 38.1441C93.1615 38.1522 93.0422 38.15 92.9795 38.1374C92.7913 38.0995 92.6386 38.1014 92.5214 38.1431C92.4042 38.1848 92.3268 38.1909 92.2891 38.1616L92.1573 38.1677L91.2032 38.3673L90.8516 38.4924L90.1987 38.6547L89.8785 38.7861L89.4955 38.9049C89.4243 38.9341 89.3553 38.9528 89.2883 38.9611C89.2214 38.9694 89.1649 38.9797 89.1188 38.9922L88.9807 39.0297L88.6352 39.2866C88.6101 39.3033 88.5891 39.3535 88.5723 39.4371L88.591 39.5062L88.547 39.5626C88.5512 39.5417 88.5429 39.5291 88.522 39.5249C88.5137 39.458 88.4782 39.4182 88.4154 39.4055L88.359 39.3615C88.2421 39.1857 88.1836 39.0977 88.1836 39.0977L88.0457 38.9721L87.9767 38.9908L87.6251 39.1159L87.5246 39.1283L87.1353 39.2784L87.0537 39.3599C87.0034 39.3933 86.9699 39.3974 86.9532 39.3723C86.9574 39.3514 86.9386 39.3367 86.8968 39.3283C86.7587 39.3658 86.6771 39.3929 86.652 39.4096C86.6268 39.4263 86.5912 39.4409 86.5452 39.4534C86.4992 39.4659 86.4489 39.4993 86.3945 39.5536C86.3818 39.6163 86.3441 39.6414 86.2814 39.6288C86.1057 39.6369 85.9718 39.5991 85.8799 39.5153C85.8632 39.4902 85.8339 39.4734 85.7921 39.465C85.6875 39.4439 85.5391 39.3705 85.3468 39.2448L85.3531 39.2134C85.3197 39.1631 85.2695 39.1422 85.2026 39.1504C85.1566 39.1629 85.1231 39.1671 85.1022 39.1629C85.031 39.1921 84.9285 39.2149 84.7946 39.2315C84.6397 39.2439 84.5352 39.2228 84.4809 39.1683ZM83.3978 37.0897L83.3664 37.0834L83.31 37.0394C83.3058 37.0603 83.2828 37.0665 83.2409 37.0581L83.2974 37.1021L83.3601 37.1148L83.3978 37.0897ZM83.1786 36.7192C83.2414 36.7318 83.2853 36.7298 83.3104 36.713L83.3418 36.7194L83.3104 36.713C83.2728 36.6837 83.2017 36.6585 83.0971 36.6375L83.0344 36.6248C83.0344 36.6248 83.0323 36.6353 83.0281 36.6562C83.0281 36.6562 83.0385 36.6583 83.0595 36.6625L83.0845 36.7002L83.1786 36.7192ZM83.3302 35.9663C83.3428 35.9035 83.3617 35.8638 83.3868 35.8471L83.5315 35.6151L83.5441 35.5523L83.5064 35.5774L83.2675 35.9536L83.2925 35.9913L83.3302 35.9663ZM83.6372 36.3871L83.6247 36.2867C83.6038 36.2825 83.5934 36.2804 83.5934 36.2804C83.5976 36.2595 83.5997 36.249 83.5997 36.249L83.6374 36.224C83.6374 36.224 83.6353 36.2344 83.6311 36.2553C83.6311 36.2553 83.6415 36.2574 83.6624 36.2616L83.6561 36.293C83.677 36.2972 83.6875 36.2993 83.6875 36.2993C83.6917 36.2784 83.6938 36.268 83.6938 36.268L83.8071 36.0296C83.8364 35.992 83.8595 35.9314 83.8763 35.8477C83.9266 35.8143 83.9329 35.7829 83.8953 35.7536L83.9016 35.7222L83.8829 35.6532C83.8829 35.6532 83.8577 35.6699 83.8075 35.7033C83.7864 35.8079 83.7487 35.8873 83.6942 35.9416L83.7193 35.9793L83.7506 35.9856L83.7757 36.0233L83.7317 36.0797C83.6732 36.0462 83.6523 36.042 83.669 36.0671C83.6647 36.088 83.6605 36.1089 83.6563 36.1298L83.6877 36.1362L83.6563 36.1298L83.625 36.1235C83.6207 36.1444 83.604 36.1737 83.5746 36.2113C83.5244 36.2447 83.516 36.2866 83.5494 36.3368C83.541 36.3786 83.5472 36.4017 83.5681 36.4059C83.5639 36.4268 83.5723 36.4393 83.5932 36.4436L83.6372 36.3871ZM84.2951 37.1724C84.3788 37.1893 84.4436 37.1914 84.4897 37.1789L84.496 37.1476L84.4646 37.1413L84.3642 37.1537L84.3705 37.1223L84.3014 37.1411C84.2805 37.1368 84.268 37.1452 84.2638 37.1661L84.2951 37.1724ZM84.7221 36.9972C84.743 37.0015 84.7535 37.0036 84.7535 37.0036C84.7577 36.9827 84.7598 36.9722 84.7598 36.9722L84.7284 36.9659C84.6657 36.9532 84.6113 36.9532 84.5652 36.9657L84.5589 36.997L84.7221 36.9972ZM84.1835 36.1054C84.1877 36.0845 84.2003 36.0761 84.2212 36.0804C84.2045 36.0552 84.2004 36.0218 84.2088 35.9799L84.1648 36.0364C84.1564 36.0782 84.1626 36.1012 84.1835 36.1054ZM83.7327 35.2639L83.7894 35.1447L83.758 35.1384L83.7077 35.2262L83.695 35.2889L83.7327 35.2639ZM84.1656 35.3837C84.1656 35.3837 84.1907 35.367 84.241 35.3336L84.1846 35.2896L84.1909 35.2582L84.1658 35.2205L84.1344 35.2142L84.1155 35.3083C84.1155 35.3083 84.1322 35.3334 84.1656 35.3837ZM84.9478 37.1733L85.7323 37.168L85.8954 37.1682L85.9331 37.1431L85.8704 37.1305L85.224 37.0983L85.1236 37.1107L85.0859 37.1358L85.0232 37.1231C84.9395 37.1063 84.8516 37.1104 84.7596 37.1354C84.7387 37.1312 84.7261 37.1395 84.7219 37.1604L84.7533 37.1667L84.9478 37.1733ZM85.5062 37.3183C85.548 37.3267 85.5815 37.3226 85.6066 37.3059L85.5188 37.2556C85.4937 37.2723 85.4602 37.2764 85.4184 37.268C85.4351 37.2931 85.4643 37.3099 85.5062 37.3183ZM85.7325 37.0048L85.7638 37.0111L85.7388 36.9734C85.5212 36.9732 85.3664 36.9855 85.2743 37.0105L85.243 37.0042C85.243 37.0042 85.2409 37.0146 85.2367 37.0356C85.2367 37.0356 85.2471 37.0377 85.268 37.0419L85.7325 37.0048ZM84.3039 35.183C84.2872 35.1579 84.3019 35.1391 84.3479 35.1266L84.3919 35.0702C84.3794 35.0241 84.4109 34.9761 84.4863 34.926C84.4905 34.905 84.503 34.8967 84.5239 34.9009C84.5281 34.88 84.5303 34.8695 84.5303 34.8695C84.5093 34.8653 84.4989 34.8632 84.4989 34.8632C84.4989 34.8632 84.478 34.859 84.4361 34.8506L84.4801 34.7942L84.5241 34.7377C84.5284 34.7168 84.5305 34.7064 84.5305 34.7064C84.5095 34.7022 84.4991 34.7001 84.4991 34.7001L84.43 34.7188C84.4174 34.7815 84.3818 34.8505 84.3231 34.9258L84.3481 34.9634L84.3168 34.9571C84.2916 34.9738 84.2644 35.001 84.2351 35.0386C84.2057 35.0762 84.189 35.1055 84.1848 35.1264L84.1721 35.1891L84.2599 35.2395L84.3039 35.183ZM85.287 36.9478C85.5087 36.9271 85.6531 36.9127 85.7201 36.9044L85.7514 36.9107L85.7201 36.9044L85.2619 36.9101L85.2556 36.9414L85.287 36.9478ZM84.1603 34.5992C84.219 34.524 84.2525 34.4654 84.261 34.4236L84.2673 34.3922L84.1353 34.5615L84.1603 34.5992ZM85.9079 37.2686C85.9831 37.3273 86.0479 37.3295 86.1024 37.2751C86.1275 37.2584 86.1715 37.2564 86.2342 37.269L86.366 37.2629C86.366 37.2629 86.3765 37.265 86.3974 37.2692C86.4392 37.2777 86.4643 37.261 86.4727 37.2191L86.5041 37.2254C86.5878 37.2423 86.6422 37.2424 86.6673 37.2256L86.705 37.2006L86.6485 37.1566C86.6234 37.1733 86.5899 37.1774 86.5481 37.169C86.4854 37.1564 86.4247 37.1877 86.366 37.2629L86.1841 37.1937L85.9142 37.2372L85.9079 37.2686ZM84.6058 34.6563C84.6477 34.6647 84.6707 34.6584 84.6749 34.6375C84.7 34.6208 84.7398 34.5853 84.7943 34.531C84.8278 34.4725 84.8404 34.4097 84.8322 34.3428C84.8155 34.3176 84.8322 34.2884 84.8825 34.255C84.8867 34.234 84.8992 34.2257 84.9202 34.2299C84.9453 34.2132 84.939 34.1902 84.9014 34.1609L84.9077 34.1295L84.8387 34.1482L84.694 34.3802L84.6814 34.443C84.6856 34.4221 84.6982 34.4137 84.7191 34.4179L84.7568 34.3929L84.7505 34.4242C84.65 34.4911 84.5997 34.5245 84.5997 34.5245L84.5494 34.6123L84.6058 34.6563ZM85.0827 34.7196C85.0618 34.7154 85.0513 34.7133 85.0513 34.7133C85.0555 34.6924 85.0577 34.6819 85.0577 34.6819L85.0513 34.7133C85.0095 34.7049 84.976 34.709 84.9509 34.7257L84.9446 34.7571L84.9696 34.7948L85.0827 34.7196ZM86.8368 37.1945C86.8786 37.2029 86.9121 37.1988 86.9372 37.1821L86.9435 37.1507L86.8494 37.1317L86.8431 37.1631L86.749 37.1442C86.7657 37.1693 86.7949 37.1861 86.8368 37.1945ZM85.0271 34.0229L85.0585 34.0293L85.0648 33.9979C85.0523 33.9519 85.0565 33.9309 85.0774 33.9351C85.1026 33.9184 85.1256 33.9122 85.1465 33.9164C85.1507 33.8955 85.1779 33.8683 85.2282 33.8349C85.2324 33.814 85.2366 33.7931 85.2408 33.7722C85.2241 33.7471 85.2157 33.7345 85.2157 33.7345C85.1739 33.7261 85.1488 33.7428 85.1404 33.7846L84.977 33.9476L84.9581 34.0417L85.0271 34.0229ZM85.8663 35.367L86.0047 35.1664L85.9796 35.1287C85.9796 35.1287 85.9692 35.1266 85.9482 35.1224C85.9482 35.1224 85.9461 35.1328 85.9419 35.1537L85.8036 35.3544L85.791 35.4171L85.8663 35.367ZM86.7997 36.73C86.7788 36.7258 86.7683 36.7237 86.7683 36.7237C86.7725 36.7028 86.7746 36.6923 86.7746 36.6923C86.7537 36.6881 86.7307 36.6944 86.7056 36.7111C86.7056 36.7111 86.6951 36.709 86.6742 36.7048C86.67 36.7257 86.6888 36.7404 86.7306 36.7488L86.7997 36.73ZM85.3846 34.1928C85.3804 34.2138 85.3888 34.2263 85.4097 34.2305C85.4139 34.2096 85.416 34.1992 85.416 34.1992L85.4036 34.0987C85.3826 34.0945 85.3701 34.1029 85.3659 34.1238C85.3575 34.1656 85.3637 34.1886 85.3846 34.1928ZM88.5969 39.8011C88.6011 39.7802 88.6032 39.7698 88.6032 39.7698C88.6075 39.7489 88.6347 39.7217 88.6849 39.6883C88.7016 39.7134 88.6995 39.7239 88.6786 39.7197C88.6744 39.7406 88.6472 39.7677 88.5969 39.8011ZM87.0757 36.8182C87.0966 36.8225 87.1071 36.8246 87.1071 36.8246C87.1113 36.8036 87.1134 36.7932 87.1134 36.7932L87.082 36.7869C87.0402 36.7785 86.9733 36.7867 86.8812 36.8117L86.9125 36.818L87.0757 36.8182ZM87.0319 36.7115C87.0738 36.7199 87.1072 36.7158 87.1324 36.6991C87.1366 36.6782 87.1178 36.6635 87.0759 36.6551C87.0759 36.6551 87.0508 36.6718 87.0006 36.7052C87.0006 36.7052 86.9984 36.7156 86.9942 36.7366C87.0152 36.7408 87.0277 36.7324 87.0319 36.7115ZM85.3162 33.7221L85.4168 33.5465L85.4358 33.4524C85.44 33.4315 85.4421 33.421 85.4421 33.421C85.4212 33.4168 85.4107 33.4147 85.4107 33.4147C85.3898 33.4105 85.3772 33.4188 85.373 33.4397L85.3667 33.4711L85.3541 33.5339C85.2913 33.5212 85.2515 33.5567 85.2347 33.6404C85.2096 33.6571 85.2054 33.678 85.2221 33.7031C85.2221 33.7031 85.2325 33.7052 85.2534 33.7094L85.3162 33.7221ZM85.4916 33.9859C85.4958 33.965 85.5083 33.9566 85.5292 33.9608C85.5335 33.9399 85.546 33.9316 85.5669 33.9358L85.5606 33.9671L85.5543 33.9985L85.5857 34.0048L85.6046 33.9107L85.6109 33.8793C85.5691 33.8709 85.5461 33.8772 85.5419 33.8981L85.5042 33.9231L85.4916 33.9859ZM87.2138 36.7808C87.2975 36.7976 87.3854 36.7935 87.4774 36.7685L87.5088 36.7749C87.513 36.754 87.5047 36.7414 87.4837 36.7372L87.2138 36.7808ZM88.598 38.9853C88.6398 38.9937 88.7067 38.9854 88.7988 38.9605L88.8365 38.9354L88.8051 38.9291L88.5792 38.9162C88.575 38.9372 88.5625 38.9455 88.5415 38.9413L88.598 38.9853ZM85.5678 33.2831C85.572 33.2622 85.5845 33.2538 85.6054 33.258C85.6097 33.2371 85.6222 33.2288 85.6431 33.233L85.7248 33.1515C85.7081 33.1264 85.7123 33.1055 85.7375 33.0888C85.7626 33.0721 85.7751 33.0637 85.7751 33.0637C85.8422 32.9466 85.9009 32.8714 85.9511 32.838L86.0832 32.6687L86.0958 32.606C86.0833 32.56 86.0519 32.5536 86.0017 32.587C85.9975 32.608 85.966 32.656 85.9074 32.7313L85.7817 32.8692L85.6433 33.0698C85.5847 33.1451 85.5532 33.1931 85.549 33.214C85.5239 33.2307 85.5092 33.2496 85.505 33.2705C85.5008 33.2914 85.4861 33.3102 85.461 33.3269C85.4568 33.3478 85.4547 33.3583 85.4547 33.3583C85.4338 33.3541 85.4233 33.3519 85.4233 33.3519L85.4798 33.3959L85.5678 33.2831ZM87.7669 36.1413L87.7355 36.135C87.7146 36.1308 87.679 36.1454 87.6288 36.1788L87.6225 36.2102L87.7669 36.1413ZM86.1084 32.5432C86.1293 32.5475 86.1398 32.5496 86.1398 32.5496C86.1649 32.5329 86.19 32.5162 86.2152 32.4995L86.165 32.4241L86.052 32.4992L86.1084 32.5432ZM88.4072 36.0417C88.3695 36.0124 88.3173 36.0019 88.2503 36.0102C88.2085 36.0017 88.175 36.0059 88.1499 36.0226L88.1059 36.079L88.1686 36.0917L88.4072 36.0417ZM86.3411 32.1984L86.3661 32.2361C86.3703 32.2152 86.3724 32.2047 86.3724 32.2047C86.3933 32.2089 86.4038 32.211 86.4038 32.211L86.4101 32.1796L86.316 32.1607L86.272 32.2171L86.3411 32.1984ZM88.7021 36.0358C88.7063 36.0149 88.7294 36.0087 88.7712 36.0171L88.6834 35.9668L88.6143 35.9855L88.5766 36.0106L88.608 36.0169L88.7021 36.0358ZM88.959 36.3813L89.0657 36.3375C89.0406 36.3542 89.0071 36.3584 88.9653 36.35L88.8962 36.3687L88.8649 36.3624L88.8962 36.3687L88.959 36.3813ZM86.5421 32.0104C86.5463 31.9894 86.561 31.9706 86.5861 31.9539C86.6112 31.9372 86.6155 31.9163 86.5988 31.8912L86.6364 31.8661L86.7244 31.7533C86.7329 31.7115 86.7266 31.6884 86.7057 31.6842L86.6617 31.7407L86.6177 31.7971L86.5297 31.9099C86.5255 31.9309 86.5108 31.9497 86.4857 31.9664L86.4417 32.0228C86.4417 32.0228 86.4396 32.0332 86.4354 32.0542C86.4563 32.0584 86.4689 32.05 86.4731 32.0291L86.5421 32.0104ZM89.9437 36.8407C89.9646 36.8449 89.9772 36.8366 89.9814 36.8157C89.9605 36.8115 89.9312 36.7947 89.8936 36.7653C89.856 36.736 89.8246 36.7297 89.7995 36.7464C89.7786 36.7422 89.7221 36.7526 89.63 36.7776L89.5923 36.8026L89.6237 36.8089L89.6864 36.8216L89.7178 36.8279C89.7052 36.8906 89.7114 36.9136 89.7365 36.8969C89.7616 36.8802 89.7847 36.874 89.8056 36.8782L89.9437 36.8407ZM86.9004 31.5276C86.9047 31.5067 86.9319 31.4795 86.9821 31.4461L86.9634 31.3771L86.8817 31.4585L86.9004 31.5276ZM89.8241 37.1104C89.9705 37.1399 90.0876 37.1526 90.1755 37.1485C90.3094 37.132 90.4559 37.107 90.6149 37.0738C90.6567 37.0822 90.6797 37.0759 90.684 37.055L90.6212 37.0424L90.5585 37.0298L90.3953 37.0296C90.274 36.9834 90.1757 36.9854 90.1003 37.0355L89.8304 37.0791C89.8095 37.0748 89.797 37.0832 89.7927 37.1041L89.8241 37.1104ZM89.9576 35.799L89.9639 35.7676L89.9011 35.755L89.8007 35.7674L89.763 35.7924L89.8195 35.8364L89.9576 35.799ZM90.114 36.1569C90.2019 36.1528 90.3379 36.1258 90.522 36.0758L90.5597 36.0508L90.497 36.0381L90.4342 36.0255L90.4092 35.9878L90.4029 36.0192C90.3944 36.061 90.3693 36.0777 90.3275 36.0693C90.3108 36.0442 90.3024 36.0316 90.3024 36.0316L90.2774 35.9939C90.269 36.0357 90.2752 36.0588 90.2961 36.063C90.2961 36.063 90.294 36.0734 90.2898 36.0943C90.2898 36.0943 90.3003 36.0965 90.3212 36.1007L90.2584 36.088C90.2333 36.1047 90.1998 36.1089 90.158 36.1005C90.1371 36.0962 90.1141 36.1025 90.089 36.1192L90.0513 36.1442L90.114 36.1569ZM91.2507 35.537C91.2549 35.5161 91.2675 35.5078 91.2884 35.512L91.552 35.4998L91.9977 35.3936L92.0291 35.4L92.0855 35.444L92.0478 35.469C91.9766 35.4982 91.8741 35.5211 91.7402 35.5377C91.6063 35.5542 91.5289 35.5604 91.508 35.5562L91.4389 35.5749C91.3762 35.5623 91.3511 35.579 91.3636 35.625L91.2507 35.537ZM92.6887 34.8799L92.7767 34.7671C92.8018 34.7504 92.8457 34.7483 92.9085 34.7609L92.9022 34.7923C92.8519 34.8257 92.8561 34.8592 92.9146 34.8927L92.946 34.8991L92.9146 34.8927L92.6887 34.8799ZM93.7801 35.2955C93.7592 35.2913 93.7488 35.2892 93.7488 35.2892C93.753 35.2683 93.7551 35.2578 93.7551 35.2578C93.6297 35.1238 93.5608 35.0337 93.5483 34.9877C93.5358 34.9416 93.5108 34.904 93.4731 34.8746C93.4564 34.8495 93.4376 34.8348 93.4167 34.8306L93.2098 34.7237L93.078 34.7298L93.0466 34.7235L93.078 34.7298L93.2161 34.6923L93.3352 34.7489C93.3562 34.7531 93.3645 34.7657 93.3603 34.7866C93.3812 34.7908 93.3938 34.7825 93.398 34.7616C93.4231 34.7449 93.444 34.7491 93.4607 34.7742L93.5172 34.8182C93.6675 35.0443 93.7468 35.1909 93.7551 35.2578C93.776 35.262 93.7843 35.2746 93.7801 35.2955ZM98.0812 41.3515C97.9767 41.3304 97.891 41.2697 97.8242 41.1692L97.705 41.1125C97.5586 41.0831 97.4437 41.0055 97.3601 40.8799C97.2807 40.8421 97.2159 40.7856 97.1658 40.7102C97.0948 40.6306 96.9965 40.5782 96.871 40.5529C96.8459 40.5696 96.8041 40.5612 96.7456 40.5277C96.687 40.4941 96.6369 40.4731 96.595 40.4647L96.2251 40.1944C96.1166 39.9767 95.9767 39.8071 95.8053 39.6855C95.6924 39.5975 95.6046 39.5472 95.5419 39.5346C95.4373 39.5135 95.3768 39.436 95.3602 39.3021C95.331 39.231 95.2202 39.1325 95.028 39.0068C94.8733 38.9103 94.7208 38.6947 94.5706 38.3598C94.5415 38.2886 94.4811 38.048 94.3896 37.6378C94.373 37.5039 94.3857 37.3868 94.4277 37.2865L94.3963 37.2801L94.5599 36.954C94.6354 36.7951 94.6795 36.6843 94.6921 36.6216L94.8054 36.3832C94.8556 36.3498 94.8996 36.2934 94.9374 36.214C94.9751 36.1345 94.9961 36.0843 95.0003 36.0634C94.9502 35.988 94.9398 35.9315 94.9692 35.8939C95.0236 35.8396 95.0529 35.802 95.0572 35.7811C95.1075 35.6389 95.1851 35.5239 95.2898 35.4362C95.3862 35.2815 95.489 35.0955 95.598 34.8781C95.64 34.7777 95.7343 34.6335 95.881 34.4454C95.9396 34.3702 96.1178 34.134 96.4153 33.7369C96.5202 33.5404 96.6166 33.3857 96.7046 33.2729C96.7968 33.1391 96.8743 33.0242 96.9372 32.928C97.0755 32.7818 97.2096 32.602 97.3396 32.3888C97.4652 32.3053 97.5448 32.1799 97.5785 32.0126L97.6351 31.8934L97.7735 31.6928C97.7944 31.697 97.8174 31.6907 97.8425 31.674C97.8676 31.6573 97.8823 31.6385 97.8865 31.6176L97.9682 31.5361C98.2029 31.2352 98.3391 31.045 98.3769 30.9655C98.49 30.836 98.5906 30.7148 98.6786 30.6019C98.7708 30.4682 98.8462 30.3637 98.9049 30.2884L99.2569 29.837C99.2904 29.7785 99.3554 29.6719 99.4518 29.5172C99.5483 29.3625 99.6509 29.2309 99.7599 29.1222C99.9023 28.9551 99.9966 28.8108 100.043 28.6896L100.332 28.2255C100.412 28.1545 100.468 28.0897 100.502 28.0312C100.54 27.9518 100.573 27.8932 100.602 27.8556C100.615 27.7929 100.665 27.7051 100.753 27.5922C100.799 27.5797 100.816 27.5505 100.804 27.5044C100.816 27.4417 100.814 27.3978 100.798 27.3726L100.635 27.2093C100.639 27.1883 100.633 27.1653 100.616 27.1402C100.624 27.0984 100.641 27.0691 100.666 27.0524C100.687 26.9478 100.681 26.8704 100.648 26.8202L100.66 26.7574L100.686 26.632C100.673 26.4771 100.732 26.4019 100.862 26.4063C100.912 26.3728 100.993 26.3458 101.106 26.325C101.378 26.2709 101.615 26.1771 101.816 26.0435C101.858 26.0519 101.885 26.0247 101.898 25.962L102.294 25.291C102.323 25.2534 102.332 25.2116 102.319 25.1655C102.328 25.1237 102.349 25.0735 102.382 25.015C102.411 24.9774 102.457 24.9105 102.52 24.8143C102.608 24.7015 102.698 24.6326 102.79 24.6076C102.966 24.4906 103.169 24.4553 103.399 24.5017C103.609 24.5438 103.763 24.5858 103.864 24.6278C103.964 24.6697 104.056 24.7535 104.139 24.8791C104.198 24.9127 104.254 24.9567 104.309 25.0111C104.363 25.0656 104.419 25.1096 104.478 25.1432C104.49 25.1892 104.534 25.2415 104.61 25.3002C104.706 25.3631 104.773 25.4092 104.81 25.4385L105.048 25.715C105.082 25.7652 105.13 25.7967 105.193 25.8093C105.414 25.7887 105.596 25.7491 105.739 25.6907C106.22 25.57 106.672 25.4869 107.095 25.4414C107.421 25.3331 107.739 25.2665 108.049 25.2418C108.342 25.192 108.572 25.1839 108.739 25.2176L108.959 25.2618L109.241 25.3187C109.262 25.3229 109.312 25.3438 109.392 25.3816C109.475 25.3984 109.532 25.4424 109.561 25.5136C109.578 25.5387 109.607 25.5555 109.649 25.5639C109.69 25.5723 109.73 25.5912 109.768 25.6206C109.785 25.6457 109.814 25.6625 109.856 25.6709C109.877 25.6751 109.885 25.6876 109.881 25.7086L109.849 25.7022C109.828 25.698 109.805 25.7043 109.78 25.721C109.776 25.7419 109.774 25.7524 109.774 25.7524L109.793 25.8214L109.755 25.8465L109.767 25.9469L109.981 26.0225C109.981 26.0225 109.997 26.0476 110.031 26.0978C110.047 26.123 110.062 26.1586 110.075 26.2046C110.091 26.2297 110.104 26.2758 110.112 26.3427C110.099 26.4054 110.112 26.4515 110.15 26.4808C110.187 26.5102 110.214 26.5374 110.231 26.5625C110.252 26.5667 110.273 26.6253 110.294 26.7383C110.331 26.7676 110.358 26.7949 110.375 26.82C110.413 26.8493 110.44 26.8766 110.457 26.9017C110.523 27.0022 110.525 27.1005 110.462 27.1966C110.437 27.3221 110.408 27.4141 110.374 27.4727L110.368 27.6672C110.372 27.7551 110.355 27.8387 110.317 27.9182L110.147 28.2757L110.009 28.4763L109.946 28.4637C109.913 28.4134 109.925 28.3507 109.984 28.2755C110.009 28.2588 110.026 28.2295 110.034 28.1877C110.047 28.1249 110.045 28.081 110.028 28.0559C110.016 28.0098 110.003 27.9638 109.991 27.9178C109.978 27.8717 109.93 27.8403 109.847 27.8234C109.826 27.8192 109.811 27.838 109.803 27.8799L109.759 27.9363L109.771 27.8735C109.755 27.8484 109.752 27.8045 109.765 27.7417L109.577 27.7039L109.483 27.6849C109.424 27.6514 109.341 27.6345 109.232 27.6344C108.914 27.7009 108.677 27.7404 108.523 27.7527C108.25 27.8068 107.845 27.8774 107.305 27.9645C106.861 28.0058 106.537 28.0493 106.332 28.0951C106.219 28.1159 106.049 28.147 105.823 28.1886C105.602 28.2092 105.415 28.2153 105.265 28.2067C105.198 28.215 105.118 28.2316 105.026 28.2566C104.959 28.2649 104.88 28.2815 104.788 28.3065C104.654 28.3231 104.587 28.3314 104.587 28.3314C104.453 28.3479 104.344 28.3478 104.261 28.3309C104.235 28.3476 104.189 28.3601 104.122 28.3684C104.06 28.3558 104.026 28.3599 104.022 28.3808L103.928 28.5251L103.55 29.102C103.492 29.1772 103.406 29.2796 103.293 29.4091C103.205 29.522 103.127 29.6369 103.06 29.754C102.913 29.9421 102.807 30.0947 102.739 30.2117C102.651 30.3246 102.553 30.4353 102.444 30.544C102.356 30.6568 102.266 30.7801 102.174 30.9139L102.048 31.0518L102.042 31.0832L102.104 31.0958L102.512 31.0147C102.642 31.0191 102.757 31.0422 102.858 31.0842C102.895 31.1135 103.019 31.1493 103.228 31.1914C103.29 31.204 103.326 31.2438 103.334 31.3107C103.351 31.3359 103.38 31.3526 103.422 31.3611C103.598 31.4617 103.706 31.5162 103.748 31.5246L103.736 31.5874L103.704 31.5811C103.683 31.5769 103.671 31.5852 103.666 31.6061C103.662 31.627 103.65 31.6354 103.629 31.6312C103.65 31.6354 103.658 31.6479 103.654 31.6689C103.65 31.6898 103.658 31.7023 103.679 31.7065L103.892 31.7821L103.924 31.7884L104.03 31.9078L103.892 31.9453C103.808 31.9285 103.754 31.9284 103.729 31.9451L103.697 31.9388C103.693 31.9597 103.702 31.9722 103.722 31.9765L103.81 32.0268L104.124 32.0899C104.166 32.0983 104.224 32.1319 104.3 32.1906C104.32 32.3036 104.36 32.3768 104.419 32.4104L104.6 32.4796C104.659 32.5132 104.684 32.5509 104.676 32.5927C104.671 32.6136 104.659 32.622 104.638 32.6177L104.4 32.5045L104.337 32.4918C104.358 32.4961 104.366 32.5086 104.362 32.5295C104.37 32.5965 104.401 32.6572 104.456 32.7116C104.535 32.7494 104.594 32.7829 104.631 32.8123L104.863 33.1201C104.863 33.1201 104.861 33.1305 104.857 33.1515C104.857 33.1515 104.867 33.1536 104.888 33.1578L104.794 33.1388C104.798 33.1179 104.79 33.1054 104.769 33.1011C104.748 33.0969 104.738 33.0948 104.738 33.0948C104.734 33.007 104.717 32.9818 104.688 33.0195C104.662 33.0362 104.639 33.0424 104.619 33.0382L104.625 33.17L104.756 33.327C104.756 33.327 104.754 33.3375 104.75 33.3584C104.767 33.3835 104.785 33.3982 104.806 33.4024C104.765 33.394 104.727 33.3647 104.694 33.3144L104.662 33.3081C104.662 33.3081 104.641 33.3039 104.599 33.2955L104.612 33.3959C104.771 33.4714 104.875 33.5469 104.925 33.6222L105.038 33.8734L105.088 33.9488C105.126 33.9781 105.119 34.0095 105.069 34.0429C105.044 34.0596 105.011 34.0637 104.969 34.0553L104.799 33.9233L104.536 33.7723C104.461 33.7137 104.434 33.7408 104.454 33.8538L104.448 33.8852L104.423 33.8475C104.41 33.8015 104.36 33.7805 104.272 33.7846L103.287 33.8147L102.365 33.8574L102.095 33.901C101.764 33.9215 101.446 33.9337 101.141 33.9375C101.032 33.9373 100.921 33.9477 100.808 33.9684C100.699 33.9683 100.57 33.9639 100.419 33.9554C100.377 33.947 100.3 33.9531 100.187 33.9739C100.078 33.9738 99.9713 33.9632 99.8667 33.9421L99.76 33.9859C99.5964 34.2577 99.4749 34.429 99.3953 34.5001L99.2382 34.6317C99.0622 34.8574 98.8674 35.1228 98.6536 35.4279C98.5656 35.5408 98.4734 35.6746 98.377 35.8292C98.3057 35.9672 98.2009 36.1093 98.0626 36.2556C97.7356 36.7991 97.5343 37.1502 97.4588 37.3091C97.4211 37.3886 97.3812 37.4785 97.3392 37.5788C97.3015 37.6583 97.27 37.7607 97.2447 37.8862C97.207 37.9657 97.232 38.0034 97.3199 37.9993C97.391 37.9701 97.4475 37.9597 97.4894 37.9681C97.5563 37.9598 97.6002 37.9578 97.6212 37.962L97.6525 37.9683C97.6316 37.9641 97.619 37.9725 97.6148 37.9934L97.2696 38.0871C97.2486 38.0829 97.2256 38.0891 97.2005 38.1058C97.2005 38.1058 97.19 38.1037 97.1691 38.0995L97.2946 38.1248L97.5519 38.1439L97.6146 38.1566L97.5769 38.1816L97.2757 38.2189C97.2087 38.2272 97.1606 38.2501 97.1312 38.2877C97.1061 38.3044 97.0977 38.3463 97.106 38.4132C97.1018 38.4341 97.0976 38.455 97.0933 38.476C97.1143 38.4802 97.1226 38.4927 97.1184 38.5136C97.11 38.5555 97.1476 38.5848 97.2312 38.6016L97.4885 38.6208C97.5555 38.6125 97.6329 38.6063 97.7208 38.6023C97.8337 38.5815 97.9425 38.5816 98.0471 38.6027L98.1098 38.6153C98.1307 38.6195 98.1517 38.6237 98.1726 38.6279C98.2144 38.6364 98.2437 38.6531 98.2604 38.6783C98.3272 38.7788 98.3962 38.8144 98.4673 38.7852L99.503 38.6673L99.9424 38.5925L100.005 38.6052C100.047 38.6136 100.114 38.6053 100.206 38.5803C100.298 38.5553 100.388 38.5408 100.476 38.5367C100.522 38.5242 100.591 38.5055 100.683 38.4805C100.8 38.4388 100.913 38.4181 101.022 38.4182C101.043 38.4224 101.189 38.3975 101.461 38.3434C101.595 38.3269 101.698 38.304 101.769 38.2748C101.861 38.2498 101.941 38.2332 102.008 38.2249C102.179 38.2377 102.267 38.2336 102.271 38.2127L102.315 38.1563C102.336 38.1605 102.344 38.173 102.34 38.1939C102.336 38.2149 102.334 38.2253 102.334 38.2253C102.409 38.1752 102.439 38.192 102.422 38.2756C102.438 38.3008 102.457 38.3154 102.478 38.3196C102.52 38.328 102.543 38.3218 102.547 38.3009L102.579 38.3072L102.641 38.3198L102.648 38.2885L102.66 38.2257C102.664 38.2048 102.677 38.1965 102.698 38.2007L102.692 38.232L102.673 38.3262C102.673 38.3262 102.648 38.3429 102.597 38.3763L102.585 38.439C102.58 38.4599 102.576 38.4808 102.572 38.5017C102.593 38.506 102.601 38.5185 102.597 38.5394C102.614 38.5646 102.668 38.619 102.76 38.7028C102.781 38.707 102.789 38.7196 102.785 38.7405C102.835 38.9246 102.891 39.023 102.954 39.0357C102.975 39.0399 102.988 39.0315 102.992 39.0106C103.017 38.9939 103.04 38.9877 103.061 38.9919L103.099 38.9668C103.099 38.9668 103.096 38.9773 103.092 38.9982C103.113 39.0024 103.134 39.0066 103.155 39.0108L103.149 39.0422L103.123 39.1677C103.144 39.1719 103.18 39.1573 103.23 39.1239C103.28 39.0905 103.308 39.0633 103.312 39.0424C103.312 39.0424 103.314 39.0319 103.318 39.011C103.343 38.9943 103.358 38.9755 103.362 38.9546C103.383 38.9588 103.391 38.9714 103.387 38.9923C103.383 39.0132 103.391 39.0258 103.412 39.03L103.406 39.0613C103.356 39.0947 103.335 39.1449 103.343 39.2119C103.36 39.237 103.362 39.2809 103.349 39.3437C103.37 39.4567 103.426 39.5007 103.518 39.4757C103.585 39.4674 103.638 39.4779 103.675 39.5073C103.721 39.6035 103.7 39.7081 103.612 39.821C103.516 39.8669 103.47 39.9337 103.474 40.0216C103.478 40.1095 103.478 40.1639 103.474 40.1848L103.41 40.4985L103.373 40.5235C103.373 40.5235 103.362 40.5214 103.341 40.5172C103.32 40.513 103.312 40.5005 103.316 40.4795C103.258 40.446 103.224 40.3957 103.216 40.3288C103.204 40.2828 103.185 40.2681 103.16 40.2848C103.051 40.3934 102.888 40.4476 102.67 40.4473C102.557 40.4681 102.423 40.4847 102.268 40.497C102.134 40.5136 101.988 40.5385 101.829 40.5718C101.695 40.5884 101.546 40.6237 101.383 40.6779L101.352 40.6716C101.314 40.6423 101.27 40.6443 101.22 40.6777C101.17 40.7111 101.134 40.7257 101.113 40.7215L101.076 40.7466L100.95 40.7213C100.917 40.7798 100.866 40.8132 100.799 40.8215C100.732 40.8298 100.688 40.8318 100.668 40.8276L100.473 40.8211C100.339 40.8377 100.228 40.9024 100.14 41.0152L100.109 41.0089C100.046 40.9963 99.9581 41.0003 99.8451 41.0211C99.7322 41.0419 99.6422 41.0564 99.5752 41.0647L99.299 41.1397C99.2781 41.1355 99.2425 41.1501 99.1923 41.1835C99.1295 41.1708 99.0982 41.1645 99.0982 41.1645L99.0354 41.1519C98.9727 41.1392 98.8953 41.1454 98.8032 41.1704C98.7069 41.2163 98.6253 41.2434 98.5583 41.2517L98.4139 41.3205L98.1754 41.3704L98.0812 41.3515ZM97.6452 38.8155L97.7205 38.7654L97.6578 38.7528C97.5951 38.7402 97.549 38.7527 97.5197 38.7903L97.482 38.8153L97.5447 38.828L97.6452 38.8155ZM96.3057 36.0651L96.3623 35.9459C96.3665 35.925 96.3582 35.9124 96.3372 35.9082L96.3309 35.9396C96.3058 35.9563 96.2869 35.996 96.2743 36.0588L96.3057 36.0651ZM97.9528 38.7469C98.0573 38.768 98.1326 38.7722 98.1787 38.7597L98.21 38.7661L98.185 38.7284L97.9528 38.7469L97.9214 38.7406C97.9214 38.7406 97.9193 38.751 97.9151 38.772C97.936 38.7762 97.9486 38.7678 97.9528 38.7469ZM96.5573 35.6261C96.6075 35.5927 96.6389 35.5446 96.6516 35.4819L96.6579 35.4505L96.6265 35.4442L96.5385 35.557L96.5259 35.6198L96.5573 35.6261ZM100.255 39.7979C100.284 39.7603 100.309 39.7436 100.33 39.7478C100.351 39.752 100.374 39.7457 100.399 39.729L100.776 39.6416C100.838 39.6543 100.916 39.6481 101.008 39.6231L101.052 39.5667L100.983 39.5854C100.765 39.5851 100.598 39.6059 100.481 39.6475C100.43 39.6809 100.359 39.7101 100.267 39.7351C100.246 39.7309 100.232 39.7497 100.223 39.7916L100.255 39.7979ZM100.375 39.2018C100.513 39.1644 100.649 39.1373 100.783 39.1208C100.917 39.1042 101.03 39.0834 101.122 39.0584L101.191 39.0397C101.149 39.0313 101.128 39.0271 101.128 39.0271L100.695 39.0704C100.649 39.0829 100.59 39.1038 100.519 39.133C100.473 39.1455 100.414 39.1663 100.343 39.1955L100.312 39.1892L100.343 39.1955L100.375 39.2018ZM101.542 38.9146C101.697 38.9023 101.823 38.8732 101.919 38.8273L102.044 38.8525L101.894 38.7896C101.752 38.848 101.636 38.8792 101.549 38.8833C101.549 38.8833 101.546 38.8937 101.542 38.9146C101.542 38.9146 101.532 38.9125 101.511 38.9083L101.542 38.9146ZM109.67 28.2123L109.683 28.1496C109.696 28.0868 109.715 28.0471 109.74 28.0304L109.771 28.0367L109.695 28.25L109.664 28.2437L109.67 28.2123ZM104.497 45.6789C104.476 45.6747 104.468 45.6621 104.472 45.6412L104.579 45.4343L104.799 44.989L105.051 44.55L105.17 44.4434C105.221 44.41 105.24 44.3703 105.227 44.3243L105.233 44.2929L105.359 44.155L105.365 44.1236L105.309 44.0796C105.309 44.0796 105.334 44.0629 105.384 44.0295C105.472 44.0255 105.516 43.969 105.516 43.8602C105.5 43.8351 105.493 43.8121 105.498 43.7912C105.519 43.7954 105.531 43.787 105.535 43.7661C105.565 43.7285 105.598 43.67 105.636 43.5905C105.695 43.5153 105.73 43.4463 105.743 43.3836C105.764 43.279 105.818 43.1703 105.906 43.0574C105.994 42.9446 106.055 42.8589 106.089 42.8004C106.122 42.7418 106.252 42.5286 106.479 42.1607C106.504 42.144 106.523 42.1043 106.535 42.0416L106.504 42.0353C106.42 42.1272 106.366 42.1815 106.341 42.1982C106.269 42.2274 106.207 42.2692 106.152 42.3235L106.02 42.4928L105.951 42.5115C105.951 42.5115 105.953 42.5011 105.957 42.4801C105.957 42.4801 105.968 42.4823 105.989 42.4865C106.047 42.4112 106.125 42.2963 106.221 42.1416C106.318 41.9869 106.421 41.8553 106.529 41.7466C106.638 41.638 106.722 41.546 106.781 41.4708C106.844 41.3747 106.892 41.2973 106.925 41.2388L106.938 41.176L106.875 41.1634L106.844 41.1571L106.875 41.1634L106.951 40.9501C106.98 40.9125 106.987 40.8811 106.97 40.856C106.974 40.8351 106.978 40.8142 106.983 40.7933L107.039 40.5109L107.077 40.4859C107.119 40.4943 107.154 40.4797 107.184 40.4421L107.272 40.3292C107.314 40.2289 107.398 40.0826 107.523 39.8903C107.528 39.8694 107.555 39.8422 107.605 39.8088C107.714 39.7001 107.785 39.6166 107.819 39.558C107.819 39.558 107.823 39.5371 107.831 39.4953C107.831 39.4953 107.821 39.4932 107.8 39.489C107.8 39.489 107.798 39.4994 107.794 39.5203L107.662 39.6896C107.662 39.6896 107.651 39.6875 107.63 39.6833C107.63 39.6833 107.628 39.6938 107.624 39.7147L107.63 39.6833L107.737 39.4763C107.771 39.4178 107.8 39.3802 107.825 39.3635C107.855 39.3259 107.882 39.2987 107.907 39.282L107.92 39.2193C107.928 39.1774 107.943 39.1586 107.964 39.1628L107.995 39.1692L108.102 38.9622L108.115 38.8995C108.161 38.887 108.2 38.8514 108.234 38.7929C108.272 38.7135 108.303 38.6654 108.328 38.6487L108.341 38.586L108.272 38.6047L108.039 38.7864C107.985 38.8407 107.941 38.8971 107.907 38.9557C107.874 39.0142 107.842 39.0623 107.813 39.0999C107.805 39.1417 107.79 39.1605 107.769 39.1563L107.725 39.2127L107.738 39.15C107.721 39.1249 107.702 39.1102 107.681 39.106C107.681 39.106 107.679 39.1165 107.675 39.1374C107.65 39.1541 107.595 39.2084 107.512 39.3003L107.178 39.6576L106.99 39.7829L106.984 39.8143C107 39.8394 106.996 39.8603 106.971 39.877C106.971 39.877 106.969 39.8875 106.965 39.9084C106.965 39.9084 106.954 39.9063 106.933 39.9021L106.531 40.2781L106.148 40.7232L105.859 41.0241L105.821 41.0491L105.827 41.0177C105.97 40.8506 106.045 40.7461 106.054 40.7042L106.186 40.535L106.349 40.372C106.374 40.3553 106.391 40.326 106.4 40.2842C106.4 40.2842 106.402 40.2738 106.406 40.2528L106.412 40.2215L106.5 40.1086L106.701 39.9206L106.708 39.8892L106.676 39.8829L106.5 40.1086C106.45 40.142 106.414 40.1566 106.393 40.1524C106.389 40.1733 106.377 40.1817 106.356 40.1775L106.362 40.1461C106.421 40.0709 106.477 40.0061 106.532 39.9518C106.59 39.8765 106.634 39.8201 106.664 39.7825L107.166 39.2309L107.324 39.0993C107.374 39.0659 107.432 38.9906 107.5 38.8736C107.504 38.8527 107.495 38.8401 107.474 38.8359L107.468 38.8673L107.236 39.049L106.582 39.7008C106.532 39.7342 106.48 39.7781 106.425 39.8324C106.392 39.8909 106.337 39.9452 106.262 39.9953L106.218 40.0518L106.186 40.0455L106.193 40.0141L106.463 39.6442C106.526 39.548 106.595 39.4749 106.67 39.4248L106.846 39.1991L107.066 38.9169L107.073 38.8856L107.041 38.8793C107.029 38.942 107.002 38.9692 106.96 38.9607L106.803 39.0923C106.798 39.1132 106.771 39.1404 106.721 39.1738L106.35 39.5562C106.35 39.5562 106.34 39.5541 106.319 39.5498C106.319 39.5498 106.317 39.5603 106.313 39.5812L106.325 39.5185L106.375 39.4307C106.426 39.3973 106.457 39.3492 106.47 39.2865C106.482 39.2237 106.501 39.184 106.526 39.1673C106.556 39.1297 106.585 39.0921 106.614 39.0544C106.753 38.9082 106.893 38.7515 107.036 38.5843C107.203 38.4004 107.383 38.2082 107.576 38.0076C107.639 37.9115 107.75 37.7924 107.909 37.6503L107.922 37.5876C107.88 37.5792 107.846 37.5833 107.821 37.6L107.696 37.7379C107.561 37.8633 107.381 38.0555 107.155 38.3146C107.126 38.3522 107.094 38.4003 107.061 38.4588C107.031 38.4964 106.992 38.5319 106.941 38.5653L106.816 38.7033L106.784 38.6969L106.791 38.6656L107.256 38.139L107.469 37.8882L107.476 37.8569L107.488 37.7941C107.547 37.7189 107.601 37.6646 107.652 37.6312C107.702 37.5978 107.763 37.5121 107.834 37.3741C107.855 37.3783 107.865 37.3804 107.865 37.3804C107.87 37.3595 107.872 37.349 107.872 37.349L107.809 37.3364C107.717 37.3614 107.65 37.3697 107.608 37.3613C107.562 37.3738 107.518 37.3758 107.476 37.3674C107.46 37.3422 107.445 37.3067 107.433 37.2606C107.382 37.1852 107.324 37.1517 107.257 37.16C107.173 37.1431 107.073 37.1012 106.956 37.0341C106.956 37.0341 106.935 37.0299 106.893 37.0215C106.876 36.9963 106.853 37.0026 106.824 37.0402C106.824 37.0402 106.814 37.0381 106.793 37.0339C106.793 37.0339 106.795 37.0234 106.799 37.0025C106.803 36.9816 106.795 36.969 106.774 36.9648C106.803 36.8184 106.751 36.7535 106.617 36.7701C106.529 36.7742 106.469 36.7511 106.435 36.7008C106.406 36.6297 106.367 36.5564 106.316 36.481C106.25 36.3805 106.193 36.2821 106.147 36.1858C106.085 36.0644 106.102 35.9264 106.198 35.7717C106.265 35.6546 106.307 35.5543 106.324 35.4706L106.337 35.4079C106.282 35.3534 106.289 35.2677 106.356 35.1506C106.44 35.0587 106.525 35.0107 106.613 35.0066C106.676 35.0192 106.779 34.9963 106.921 34.938C107.101 34.8001 107.283 34.7606 107.467 34.8194C107.551 34.8363 107.639 34.8322 107.731 34.8072C108.174 34.7659 108.503 34.7015 108.716 34.6139C108.859 34.5555 108.99 34.5494 109.112 34.5956L109.206 34.6145C109.373 34.6482 109.658 34.6402 110.059 34.5905C110.084 34.5738 110.158 34.5341 110.279 34.4715C110.459 34.2249 110.635 33.9992 110.807 33.7944C110.979 33.5896 111.123 33.412 111.241 33.2616L111.756 32.6472L112.316 31.8132L112.762 31.2176C112.791 31.18 112.905 31.0504 113.101 30.8289L113.717 30.039L114.076 29.5562L114.195 29.4497C114.199 29.4288 114.204 29.4078 114.208 29.3869C114.233 29.3702 114.235 29.3598 114.214 29.3556C114.218 29.3346 114.189 29.3179 114.126 29.3052C114.038 29.3093 113.94 29.3113 113.831 29.3111C113.743 29.3152 113.654 29.3297 113.561 29.3547L112.821 29.4667L111.691 29.7289L111.622 29.7476C111.592 29.7852 111.555 29.8103 111.509 29.8228C111.463 29.8353 111.427 29.8499 111.402 29.8666C111.335 29.8749 111.14 29.9227 110.818 30.0102C110.605 30.0978 110.485 30.1499 110.46 30.1666L109.801 30.5235L109.732 30.5422C109.753 30.5465 109.763 30.5486 109.763 30.5486C109.767 30.5276 109.769 30.5172 109.769 30.5172L110.121 30.229L110.19 30.2102C110.195 30.1893 110.199 30.1684 110.203 30.1475C110.228 30.1308 110.23 30.1203 110.209 30.1161C110.193 30.091 110.172 30.0868 110.147 30.1035C110.147 30.1035 110.136 30.1014 110.115 30.0972C110.09 30.1139 110.057 30.118 110.015 30.1096C110.027 30.0468 110.044 30.0176 110.065 30.0218C110.111 30.0093 110.142 29.9612 110.159 29.8776L110.248 29.4384C110.26 29.3756 110.258 29.3317 110.242 29.3066C110.221 29.1936 110.152 29.1579 110.035 29.1996L109.972 29.187C109.993 29.1912 110.003 29.1933 110.003 29.1933C110.008 29.1724 110.01 29.1619 110.01 29.1619L110.192 29.068C110.213 29.0722 110.248 29.0576 110.298 29.0242C110.315 28.9406 110.376 28.9093 110.481 28.9303C110.711 28.8679 110.864 28.8116 110.939 28.7615C110.964 28.7448 110.987 28.7385 111.008 28.7427C111.054 28.7302 111.102 28.7073 111.152 28.6739C111.245 28.6489 111.387 28.5905 111.579 28.4987C111.985 28.3193 112.289 28.2172 112.49 28.1924L112.521 28.1987C112.542 28.2029 112.553 28.205 112.553 28.205C112.557 28.1841 112.559 28.1736 112.559 28.1736L112.527 28.1673C112.193 28.0999 111.791 28.0952 111.323 28.1532L110.795 28.1777L110.764 28.1713C110.768 28.1504 110.77 28.14 110.77 28.14C110.791 28.1442 110.802 28.1463 110.802 28.1463C110.894 28.1213 111.107 28.0881 111.442 28.0467L111.643 28.0218L112.007 27.9972C112.074 27.9889 112.12 27.9764 112.145 27.9597C112.191 27.9472 112.227 27.9326 112.252 27.9159C112.394 27.8575 112.494 27.8451 112.553 27.8787C112.591 27.908 112.634 27.9059 112.685 27.8725L112.798 27.7974L112.804 27.766C112.829 27.7493 112.852 27.7431 112.873 27.7473C112.915 27.7557 112.948 27.7515 112.974 27.7348L112.992 27.8039L113.024 27.8102C113.158 27.7937 113.277 27.7959 113.381 27.8169L113.488 27.7732C113.517 27.7355 113.555 27.7105 113.601 27.698C113.647 27.6855 113.681 27.6814 113.702 27.6856L113.771 27.6668L113.714 27.6228L113.557 27.5912L113.231 27.5908C113.189 27.5824 113.17 27.5677 113.175 27.5468L113.206 27.5531C113.252 27.5407 113.317 27.5428 113.401 27.5597C113.426 27.543 113.459 27.5388 113.501 27.5472C113.576 27.4971 113.62 27.4951 113.633 27.5411L113.664 27.5475L113.746 27.466L113.714 27.4597C113.589 27.4344 113.482 27.4238 113.394 27.4279L113.238 27.3963L113.206 27.39C113.227 27.3942 113.24 27.3858 113.244 27.3649L113.307 27.3776L113.702 27.3592L113.834 27.3531C113.968 27.3366 114.056 27.3325 114.097 27.3409L114.392 27.335L114.813 27.3544C114.838 27.3377 114.859 27.3419 114.876 27.367C114.897 27.3712 114.92 27.365 114.945 27.3483C115.028 27.3651 115.085 27.3547 115.114 27.3171C115.19 27.267 115.242 27.2775 115.271 27.3487C115.267 27.3696 115.275 27.3821 115.296 27.3864C115.321 27.3697 115.334 27.3613 115.334 27.3613C115.384 27.3279 115.415 27.3342 115.428 27.3802L115.56 27.3741L115.892 27.3432L115.924 27.3495L115.892 27.3432C115.767 27.3179 115.681 27.3115 115.635 27.324L115.572 27.3114L115.61 27.2863L115.88 27.2428L116.307 27.2307C116.399 27.2058 116.574 27.1976 116.834 27.2063C116.968 27.1897 117.143 27.1816 117.361 27.1819C117.428 27.1736 117.516 27.1695 117.625 27.1697C117.754 27.174 117.851 27.1825 117.913 27.1951C118.152 27.1996 118.526 27.2315 119.036 27.2907C119.145 27.2908 119.304 27.312 119.513 27.3541C119.89 27.4298 120.22 27.5725 120.504 27.7821C120.818 27.954 121.067 28.1238 121.251 28.2914C121.531 28.5218 121.756 28.7522 121.927 28.9825C122.049 29.1375 122.205 29.3866 122.397 29.7299L122.61 30.1319L122.704 30.4772C122.712 30.6529 122.731 30.7763 122.76 30.8475L122.822 31.0233C122.847 31.1154 122.868 31.2284 122.885 31.3623L122.81 31.086L122.785 31.0483L122.778 31.0797L122.784 31.3747L122.778 31.4061C122.811 31.4563 122.822 31.5128 122.809 31.5755C122.796 31.6383 122.786 31.6906 122.777 31.7324L122.759 31.8265C122.754 31.8474 122.746 31.8892 122.733 31.952C122.721 32.0147 122.721 32.0691 122.733 32.1152C122.746 32.1612 122.739 32.2469 122.714 32.3724L122.708 32.4038L122.683 32.3661C122.649 32.3159 122.639 32.2594 122.651 32.1966C122.668 32.113 122.679 32.0607 122.683 32.0398L122.696 31.977L122.652 32.0335L122.507 32.5918C122.485 32.6964 122.387 32.8615 122.211 33.0872C122.085 33.2795 121.928 33.4655 121.74 33.6452C121.543 33.8667 121.214 34.1486 120.753 34.4911L119.943 35.1114L119.56 35.3933L118.982 35.6687L118.8 35.7626C118.754 35.7751 118.697 35.7855 118.63 35.7938C118.584 35.8063 118.524 35.8376 118.448 35.8877L117.914 36.1067C117.839 36.1568 117.709 36.2068 117.525 36.2568C117.433 36.2818 117.316 36.3235 117.174 36.3819C117.056 36.4235 116.916 36.4715 116.753 36.5257L116.37 36.6444C116.228 36.7028 116.018 36.7695 115.742 36.8444L115.02 37.0255C114.702 37.0921 114.466 37.1315 114.311 37.1439L113.2 37.3119C113.091 37.3117 113.06 37.3598 113.106 37.4561L113.212 37.5755L113.538 37.9022C113.576 37.9316 113.624 38.0174 113.682 38.1597L113.751 38.3041L114.12 38.9008L114.214 39.0829L114.584 39.6796L114.765 40.0752C114.857 40.2678 114.936 40.4143 115.003 40.5148C115.02 40.5399 115.06 40.5588 115.122 40.5714C115.173 40.538 115.183 40.4857 115.154 40.4146C115.133 40.4104 115.123 40.4083 115.123 40.4083C115.127 40.3873 115.129 40.3769 115.129 40.3769C115.129 40.3769 115.127 40.3873 115.123 40.4083C115.144 40.4125 115.156 40.4041 115.16 40.3832C115.202 40.3916 115.225 40.3854 115.229 40.3645L115.217 40.264L115.23 40.2013L115.248 40.2704C115.277 40.3415 115.3 40.444 115.317 40.5779C115.309 40.6198 115.313 40.6533 115.329 40.6784C115.379 40.7537 115.415 40.8479 115.436 40.9609C115.461 41.053 115.49 41.1242 115.523 41.1744L115.617 41.3565C115.742 41.5993 115.826 41.7794 115.868 41.8966L116.212 42.6187L116.412 43.0834L116.543 43.4036L116.537 43.435C116.487 43.4684 116.462 43.4851 116.462 43.4851C116.336 43.4598 116.296 43.4953 116.342 43.5916L116.543 44.0563L116.949 44.9542C116.933 44.9291 117.06 45.1614 117.331 45.6513C117.348 45.6764 117.352 45.7099 117.344 45.7517C117.302 45.7433 117.273 45.7265 117.256 45.7014C117.11 45.5632 117.018 45.4794 116.98 45.45C116.863 45.3829 116.798 45.3264 116.786 45.2803L116.692 45.2614L116.641 45.3492C116.62 45.345 116.608 45.3533 116.604 45.3742C116.62 45.3994 116.616 45.4203 116.591 45.437C116.541 45.4704 116.541 45.5248 116.591 45.6001L116.71 45.8199L116.735 45.8576L116.672 45.845L116.603 45.7006C116.536 45.6001 116.371 45.4472 116.108 45.2418L115.907 45.1035C115.891 45.0784 115.861 45.0616 115.82 45.0532C115.815 45.0741 115.803 45.0824 115.782 45.0782C115.778 45.0991 115.784 45.1222 115.801 45.1473L115.932 45.4675L115.926 45.4989C115.926 45.4989 115.915 45.4968 115.894 45.4926C115.894 45.4926 115.896 45.4821 115.901 45.4612L115.537 44.8332C115.537 44.8332 115.496 44.7704 115.412 44.6447C115.412 44.6447 115.402 44.6426 115.381 44.6384C115.381 44.6384 115.383 44.628 115.387 44.6071C115.379 44.6489 115.374 44.6698 115.374 44.6698C115.408 44.8288 115.462 44.9921 115.537 45.1595C115.529 45.2013 115.533 45.2348 115.549 45.2599C115.516 45.2097 115.499 45.1846 115.499 45.1846C115.466 45.1343 115.439 45.1071 115.418 45.1029L115.43 45.2033C115.464 45.2535 115.485 45.3121 115.493 45.3791C115.518 45.4712 115.549 45.5319 115.587 45.5612C115.608 45.5654 115.618 45.5675 115.618 45.5675C115.614 45.5884 115.612 45.5989 115.612 45.5989L115.58 45.5926C115.547 45.5423 115.52 45.5151 115.499 45.5109L115.436 45.4983C115.386 45.5317 115.319 45.54 115.235 45.5231C115.235 45.5231 115.217 45.5084 115.179 45.4791C115.137 45.4707 115.122 45.4895 115.135 45.5355L115.097 45.5606L115.053 45.4539C115.037 45.4287 115.016 45.4245 114.991 45.4412C114.995 45.4203 114.976 45.4056 114.934 45.3972C114.922 45.3512 114.878 45.2988 114.803 45.2402C114.803 45.2402 114.782 45.2359 114.74 45.2275C114.736 45.2484 114.744 45.261 114.765 45.2652L114.815 45.5038L114.802 45.5665L114.777 45.5288L114.583 45.1959L114.552 45.1896L114.545 45.221L114.558 45.3214L114.645 45.5349L114.639 45.5663C114.589 45.4909 114.535 45.3821 114.476 45.2397C114.455 45.2355 114.437 45.2209 114.42 45.1957C114.42 45.1957 114.407 45.2041 114.382 45.2208L114.326 45.1768L114.226 44.8629C114.134 44.6703 113.975 44.3772 113.75 43.9837C113.737 43.9376 113.706 43.8769 113.656 43.8016C113.623 43.7513 113.602 43.6927 113.594 43.6258C113.527 43.5253 113.493 43.475 113.493 43.475C113.439 43.4206 113.383 43.3222 113.324 43.1798L113.218 43.0605L112.93 42.5455L112.56 41.9488L111.959 41.0444L111.52 40.4664L111.125 39.9953L110.75 39.43L110.518 39.1222L110.28 38.8457C110.221 38.8122 110.177 38.8142 110.148 38.8518L109.897 39.1276L109.224 39.8736L108.778 40.3061L108.068 41.0771L107.81 41.3843C107.789 41.38 107.777 41.3884 107.772 41.4093C107.743 41.5557 107.661 41.6916 107.527 41.8169C107.435 41.9507 107.322 42.0802 107.188 42.2056L106.93 42.5128C106.871 42.588 106.79 42.6695 106.685 42.7572C106.601 42.8491 106.513 42.962 106.421 43.0958C106.019 43.5806 105.728 43.9463 105.547 44.1929L105.183 44.5439C105.036 44.732 104.858 45.0225 104.648 45.4155L104.504 45.6475L104.497 45.6789ZM104.952 43.7466L105.172 43.4644L105.203 43.4708L105.197 43.5021L105.109 43.615L104.983 43.7529L104.945 43.7779L104.952 43.7466ZM105.762 42.8L105.901 42.5993L105.92 42.6684L105.794 42.8063L105.762 42.8ZM105.832 42.4549L105.801 42.4486C105.868 42.3315 105.939 42.1935 106.014 42.0346C106.04 42.0179 106.056 41.9887 106.065 41.9468C106.073 41.905 106.09 41.8758 106.115 41.8591C106.119 41.8381 106.132 41.8298 106.153 41.834L106.14 41.8967L106.134 41.9281C106.138 41.9072 106.151 41.8988 106.172 41.9031L106.241 41.8843L106.197 41.9407C106.188 41.9826 106.155 42.0411 106.096 42.1163C106.071 42.133 106.052 42.1728 106.039 42.2355L105.995 42.2919L105.863 42.4612L105.819 42.5176L105.832 42.4549ZM106.209 41.7148C106.218 41.673 106.235 41.6437 106.26 41.627L106.398 41.4264C106.406 41.3846 106.44 41.326 106.499 41.2508L106.536 41.2257L106.53 41.2571C106.446 41.4578 106.348 41.623 106.234 41.7525C106.234 41.7525 106.224 41.7504 106.203 41.7462C106.203 41.7462 106.201 41.7567 106.197 41.7776L106.209 41.7148ZM106.31 41.8656C106.335 41.8489 106.354 41.8091 106.366 41.7464C106.391 41.7297 106.417 41.713 106.442 41.6963C106.471 41.6587 106.502 41.6106 106.536 41.5521C106.561 41.5354 106.586 41.5187 106.611 41.502C106.641 41.4643 106.672 41.4163 106.706 41.3577L106.737 41.3641L106.643 41.5083L106.398 41.7527C106.389 41.7946 106.36 41.8322 106.31 41.8656ZM106.555 41.1316C106.564 41.0898 106.578 41.071 106.599 41.0752C106.608 41.0334 106.633 41.0167 106.675 41.0251C106.666 41.0669 106.652 41.0857 106.631 41.0815C106.622 41.1233 106.608 41.1422 106.587 41.1379L106.555 41.1316ZM106.912 41.6279L107 41.515C107.026 41.4983 107.04 41.4795 107.044 41.4586C107.049 41.4377 107.04 41.4251 107.019 41.4209C106.978 41.4125 106.944 41.4166 106.919 41.4333C106.906 41.4961 106.887 41.5358 106.862 41.5525L106.856 41.5839L106.875 41.6529L106.912 41.6279ZM106.769 40.8809L106.813 40.8244L106.863 40.8998C106.855 40.9416 106.84 40.9605 106.819 40.9562L106.675 41.0251L106.769 40.8809ZM106.982 41.1196C107.007 41.1029 107.032 41.0862 107.057 41.0695C107.087 41.0319 107.106 40.9922 107.114 40.9503C107.185 40.8124 107.234 40.735 107.259 40.7183C107.28 40.7225 107.29 40.7246 107.29 40.7246C107.294 40.7037 107.296 40.6933 107.296 40.6933C107.284 40.6472 107.29 40.6159 107.315 40.5992C107.366 40.5658 107.403 40.5407 107.428 40.524L107.447 40.4299L107.372 40.48L107.334 40.505L107.02 40.9314C106.995 40.9481 106.978 40.9774 106.97 41.0192C106.965 41.0401 106.951 41.0589 106.926 41.0756L106.944 41.1447L106.982 41.1196ZM108.379 38.5609C108.429 38.5275 108.456 38.5003 108.46 38.4794L108.435 38.4417C108.385 38.4751 108.36 38.4918 108.36 38.4918L108.379 38.5609ZM116.556 43.6672C116.56 43.6463 116.562 43.6358 116.562 43.6358C116.583 43.64 116.593 43.6421 116.593 43.6421C116.627 43.6924 116.643 43.7175 116.643 43.7175L116.599 43.7739L116.556 43.6672ZM116.368 42.8134L116.312 42.6063C116.337 42.6983 116.366 42.7695 116.4 42.8198L116.368 42.8134ZM116.312 42.6063C116.262 42.5309 116.208 42.4221 116.149 42.2797L115.924 41.7774L115.93 41.746C115.951 41.7502 115.96 41.7628 115.956 41.7837L116.093 42.0726L116.293 42.5372L116.312 42.6063ZM114.778 39.6861C114.757 39.6819 114.749 39.6693 114.753 39.6484C114.703 39.5731 114.638 39.5165 114.559 39.4787C114.542 39.4536 114.536 39.4306 114.54 39.4097C114.549 39.3679 114.545 39.3344 114.528 39.3093L114.635 39.2655C114.651 39.2906 114.668 39.3157 114.685 39.3408C114.701 39.366 114.708 39.389 114.703 39.4099C114.699 39.4308 114.716 39.5103 114.753 39.6484C114.774 39.6526 114.783 39.6652 114.778 39.6861ZM113.959 27.5415C114.009 27.5081 114.055 27.4956 114.097 27.5041C114.139 27.5125 114.17 27.5188 114.191 27.523C114.196 27.5021 114.208 27.4938 114.229 27.498L114.204 27.4603C114.162 27.4519 114.108 27.4518 114.041 27.4601C113.995 27.4726 113.959 27.4872 113.934 27.5039L113.959 27.5415ZM114.679 34.1822C114.771 34.1572 114.827 34.1468 114.848 34.151L115.438 33.976C115.899 33.8511 116.236 33.7449 116.449 33.6573L117.504 33.2821C117.621 33.2404 117.715 33.2049 117.786 33.1757C117.883 33.1298 117.966 33.0923 118.038 33.0631L118.684 32.769C119.036 32.5351 119.308 32.3723 119.501 32.2805C119.819 32.1052 120.142 31.8546 120.468 31.5286L120.826 31.209L120.87 31.1526C120.875 31.1317 120.881 31.1003 120.889 31.0585C120.923 31 120.967 30.9435 121.021 30.8892C121.084 30.7931 121.091 30.7073 121.04 30.6319C121.02 30.6277 121.009 30.6256 121.009 30.6256C121.013 30.6047 121.015 30.5942 121.015 30.5942C121.011 30.5064 120.98 30.4457 120.922 30.4121L120.545 30.1732L120.439 30.0538C120.422 30.0287 120.416 30.0057 120.42 29.9847C120.424 29.9638 120.416 29.9513 120.395 29.9471L120.069 29.7835L119.805 29.6325L119.686 29.5759L119.856 29.5447L119.887 29.551L119.918 29.5574L119.887 29.551C119.85 29.5217 119.768 29.4944 119.642 29.4691L119.354 29.4437C119.207 29.4142 119.107 29.4266 119.053 29.4809L119.015 29.506C118.927 29.5101 118.808 29.5622 118.657 29.6624L118.267 29.9757C118.016 30.1428 117.826 30.3329 117.696 30.5461C117.469 30.8052 117.331 30.9515 117.281 30.9849C117.252 31.0225 117.224 31.0496 117.199 31.0663C117.178 31.0621 117.149 31.0454 117.111 31.016L116.999 30.928C116.848 31.0282 116.772 31.0784 116.772 31.0784L116.32 31.8685C116.148 32.1821 115.976 32.4413 115.804 32.6461L115.553 32.9219L114.654 33.9813L114.49 34.1443C114.49 34.1443 114.478 34.1526 114.453 34.1693C114.449 34.1903 114.457 34.2028 114.478 34.207C114.469 34.2489 114.49 34.2531 114.541 34.2197L114.679 34.1822ZM117.124 30.9533C117.166 30.9617 117.189 30.9555 117.193 30.9345C117.218 30.9178 117.237 30.8781 117.25 30.8154C117.283 30.7569 117.323 30.7213 117.369 30.7088C117.373 30.6879 117.365 30.6754 117.344 30.6712C117.344 30.6712 117.334 30.6691 117.313 30.6648C117.313 30.6648 117.311 30.6753 117.306 30.6962L117.105 30.8842C117.101 30.9051 117.089 30.9135 117.068 30.9093L117.124 30.9533ZM122.695 32.7929L122.745 32.7051L122.751 32.8369L122.688 32.8243C122.684 32.8452 122.671 32.8535 122.651 32.8493L122.695 32.7929ZM122.897 31.6259C122.897 31.6259 122.886 31.6237 122.865 31.6195C122.865 31.6195 122.868 31.6091 122.872 31.5882L122.885 31.3623C122.901 31.3874 122.914 31.4334 122.922 31.5004C122.93 31.5673 122.932 31.6113 122.928 31.6322L122.897 31.6259ZM120.203 44.7605C120.14 44.7479 120.054 44.6871 119.946 44.5782C119.929 44.5531 119.831 44.4462 119.651 44.2577L119.626 44.2201C119.639 44.1573 119.603 44.1175 119.52 44.1007C119.432 44.1048 119.396 44.065 119.413 43.9813L119.394 43.9123C119.319 43.8536 119.315 43.7657 119.382 43.6487L119.42 43.2973C119.403 43.2721 119.406 43.2617 119.427 43.2659L119.816 42.6263C119.896 42.4465 120.055 42.25 120.294 42.037C120.399 41.9492 120.481 41.8678 120.539 41.7925C120.623 41.7006 120.692 41.6275 120.747 41.5731L120.891 41.3411C120.946 41.2868 121.015 41.2681 121.098 41.2849C121.115 41.31 121.134 41.3247 121.155 41.3289C121.18 41.3122 121.203 41.3059 121.224 41.3102L121.287 41.3228L121.243 41.3792L121.155 41.4921C120.991 41.655 120.897 41.7449 120.872 41.7616C120.763 41.8702 120.692 41.9538 120.658 42.0123L120.105 42.6517L119.992 42.8901L119.985 42.9214L120.017 42.9278L120.3 42.6583L120.57 42.2883L120.953 41.8432L121.085 41.674L121.249 41.511C121.253 41.4901 121.255 41.4796 121.255 41.4796C121.276 41.4839 121.295 41.4985 121.311 41.5236L121.362 41.599C121.37 41.666 121.412 41.6744 121.487 41.6243L121.663 41.5617L121.726 41.5744C121.83 41.5954 121.895 41.652 121.92 41.7441L122.008 41.7944L122.302 41.9517L122.296 41.983C122.267 42.0206 122.263 42.0416 122.284 42.0458C122.304 42.05 122.325 42.0542 122.346 42.0584L122.522 42.159C122.597 42.2177 122.656 42.2512 122.697 42.2597C122.777 42.2974 122.808 42.3581 122.791 42.4418C122.8 42.5087 122.777 42.5694 122.722 42.6237L122.628 42.6047L122.528 42.6172C122.519 42.659 122.523 42.6925 122.54 42.7176L122.565 42.7553C122.598 42.8055 122.592 42.8369 122.546 42.8494L122.427 42.9559L122.395 42.9496L122.402 42.9182L122.383 42.8492L122.339 42.9056C122.171 43.0895 122.039 43.2044 121.943 43.2503L121.905 43.2753C121.922 43.3004 121.918 43.3214 121.893 43.3381C121.872 43.3339 121.859 43.3422 121.855 43.3631C121.784 43.3923 121.729 43.4466 121.692 43.5261C121.658 43.5846 121.639 43.6243 121.635 43.6452C121.631 43.6662 121.614 43.6954 121.585 43.733C121.56 43.7497 121.524 43.7643 121.478 43.7768C121.507 43.848 121.497 43.9003 121.446 43.9337C121.4 43.9462 121.377 43.9524 121.377 43.9524L121.34 43.9775C121.335 43.9984 121.344 44.011 121.365 44.0152L121.553 44.0531C121.574 44.0573 121.586 44.0489 121.591 44.028L121.566 43.9903C121.52 44.0028 121.513 43.9798 121.547 43.9213L121.56 43.8585C121.618 43.6745 121.798 43.4823 122.1 43.2818L122.27 43.0875L122.345 43.0374L122.559 42.9498C122.63 42.9206 122.682 42.9311 122.715 42.9814C122.711 43.0023 122.719 43.0149 122.74 43.0191C122.761 43.0233 122.78 43.038 122.797 43.0631C122.797 43.0631 122.816 43.0777 122.853 43.1071C122.891 43.1364 122.893 43.1804 122.859 43.2389C122.914 43.2933 122.895 43.3331 122.803 43.358L122.439 43.5459L121.974 43.9093C121.873 43.9761 121.844 44.0681 121.885 44.1853C121.906 44.2983 121.858 44.3756 121.741 44.4173C121.674 44.4256 121.657 44.4548 121.69 44.5051L121.646 44.5615C121.554 44.5865 121.494 44.6178 121.464 44.6554C121.456 44.6972 121.42 44.7118 121.358 44.6992C121.295 44.6866 121.247 44.7095 121.213 44.7681C121.15 44.8642 121.056 44.8997 120.931 44.8744C120.78 44.8658 120.537 44.8279 120.203 44.7605ZM121.171 43.6823L121.158 43.5819C121.083 43.632 121.045 43.657 121.045 43.657C121.037 43.6989 121.049 43.7449 121.083 43.7952L121.171 43.6823ZM120.788 43.1484C120.772 43.1233 120.753 43.1086 120.732 43.1044C120.736 43.0835 120.728 43.0709 120.707 43.0667L120.669 43.0918L120.726 43.1358L120.788 43.1484ZM126.315 35.1539L126.284 35.1476L126.265 35.0785L126.303 35.0534L126.24 35.0408L126.196 35.0972L126.277 35.1789L126.315 35.1539ZM126.033 34.9339C126.158 34.9591 126.24 34.932 126.278 34.8526L126.353 34.8025L126.359 34.7711L126.334 34.7334C126.284 34.7668 126.255 34.7501 126.247 34.6831L126.215 34.6768L126.203 34.7395L126.196 34.7709L126.046 34.8711C126.025 34.8669 126.012 34.8753 126.008 34.8962L126.033 34.9339ZM126.798 35.0227L126.805 34.9913L126.742 34.9787C126.7 34.9703 126.673 34.9974 126.66 35.0602L126.798 35.0227ZM127.036 35.4623C127.02 35.4372 127.036 35.4079 127.087 35.3745L127.124 35.3494C127.129 35.3285 127.118 35.3264 127.093 35.3431C127.072 35.3389 127.047 35.3556 127.018 35.3932C126.992 35.4099 126.978 35.4288 126.974 35.4497L126.936 35.4747L127.03 35.4937L127.036 35.4623ZM126.138 36.1954C125.971 36.1617 125.82 36.0988 125.686 36.0066C125.649 35.9772 125.588 35.8998 125.505 35.7741C125.509 35.7532 125.513 35.7323 125.517 35.7114C125.526 35.6696 125.513 35.6235 125.48 35.5733C125.492 35.5105 125.482 35.454 125.449 35.4038C125.415 35.3535 125.39 35.3159 125.373 35.2907L125.348 35.2531C125.357 35.2112 125.355 35.1673 125.342 35.1213C125.334 35.0543 125.334 34.9999 125.343 34.9581C125.347 34.9372 125.418 34.7448 125.557 34.381L125.808 33.942L126.016 33.5595C126.091 33.4006 126.19 33.2898 126.311 33.2272L126.456 33.1584L126.694 33.1085C126.74 33.096 126.826 33.1024 126.951 33.1276C127.181 33.1739 127.332 33.2369 127.403 33.3165L127.459 33.3605C127.501 33.3689 127.549 33.4003 127.604 33.4548C127.658 33.5092 127.708 33.5302 127.754 33.5177C127.796 33.5262 127.813 33.5513 127.804 33.5931C127.817 33.6391 127.854 33.6685 127.917 33.6811L128.074 33.7127C128.116 33.7211 128.13 33.7567 128.118 33.8194L128.155 33.9575L128.168 34.058L128.193 34.0957C128.239 34.0832 128.279 34.102 128.312 34.1523L128.494 34.3847C128.548 34.4392 128.575 34.5208 128.575 34.6296L128.569 34.661L128.493 34.7111C128.364 34.7067 128.261 34.784 128.185 34.9429L128.06 35.0808C128.051 35.1226 128.074 35.1707 128.129 35.2252C128.191 35.2378 128.208 35.263 128.179 35.3006L128.091 35.4134L127.946 35.4823C127.921 35.499 127.888 35.5031 127.846 35.4947C127.804 35.4863 127.777 35.5134 127.764 35.5762C127.752 35.6389 127.735 35.6682 127.714 35.664C127.714 35.664 127.699 35.6284 127.67 35.5572L127.664 35.5886L127.626 35.6137C127.613 35.6764 127.572 35.7224 127.5 35.7516L127.456 35.808L127.475 35.8771C127.467 35.9189 127.45 35.9481 127.425 35.9648C127.4 35.9816 127.366 35.9857 127.324 35.9773L127.255 35.996L127.105 36.0962L126.828 36.1712C126.824 36.1921 126.766 36.2129 126.653 36.2337L126.627 36.196C126.494 36.2126 126.385 36.2125 126.301 36.1956L126.138 36.1954ZM127.721 35.1431L127.74 35.049L127.746 34.8545L127.753 34.8231L127.715 34.8481L127.702 34.9109L127.665 34.9359C127.627 34.9066 127.606 34.9024 127.602 34.9233C127.619 34.9484 127.625 34.9714 127.621 34.9924L127.608 35.0551C127.6 35.0969 127.606 35.1199 127.627 35.1242L127.721 35.1431ZM127.74 34.7227C127.744 34.7017 127.736 34.6892 127.715 34.685L127.665 34.7728L127.696 34.7791L127.74 34.7227ZM127.878 34.522L127.916 34.497L127.998 34.4155C128.002 34.3946 127.994 34.382 127.973 34.3778L127.929 34.4342L127.891 34.4593L127.872 34.3902L127.916 34.3338C127.866 34.3672 127.841 34.3839 127.841 34.3839L127.81 34.3776L127.734 34.4277L127.759 34.4654L127.753 34.4967L127.791 34.4717L127.86 34.453L127.853 34.4843L127.803 34.5721L127.878 34.522ZM134.818 47.6375C134.696 47.5914 134.563 47.4991 134.416 47.3609C134.362 47.3064 134.22 47.2017 133.99 47.0466C133.714 46.7952 133.535 46.4979 133.451 46.1547C133.385 45.9454 133.362 45.7341 133.383 45.5208C133.375 45.4538 133.381 45.3681 133.402 45.2635C133.423 45.1589 133.43 45.0732 133.422 45.0062L133.434 44.7803L133.435 44.6171C133.518 44.5252 133.552 44.4123 133.535 44.2784C133.51 44.1863 133.552 44.086 133.661 43.9773C133.766 43.8896 133.835 43.7621 133.869 43.5948L133.932 43.1179C133.937 43.097 133.928 43.0844 133.907 43.0802C133.886 43.076 133.878 43.0634 133.882 43.0425L133.914 42.8857L133.945 42.7288L133.977 42.572C134.179 41.7856 134.397 41.0789 134.632 40.4516C134.842 39.9498 135.067 39.4836 135.306 39.053L135.947 37.9744L136.922 36.5384L137.456 35.83C137.674 35.6127 137.802 35.4099 137.84 35.2217L137.928 35.1089L138.883 34.0934C139.046 33.9304 139.249 33.8408 139.492 33.8243L140 33.7308C140.092 33.7059 140.222 33.7102 140.389 33.7439C140.557 33.7776 140.705 33.851 140.835 33.9641C140.985 34.0814 141.077 34.2196 141.11 34.3786L141.179 34.5231C141.221 34.6403 141.221 34.7491 141.179 34.8494C141.145 34.9079 141.107 34.9874 141.065 35.0877C141.023 35.1881 140.996 35.2697 140.984 35.3324C140.853 35.7632 140.696 36.1123 140.512 36.3798C140.277 36.6808 140.042 37.0361 139.807 37.4458L139.405 38.1482L139.115 38.6122L139.046 38.631L139.059 38.5682L139.481 37.7717C139.51 37.7341 139.531 37.6839 139.544 37.6212L139.393 37.7214C139.347 37.7339 139.315 37.782 139.298 37.8656C139.286 37.9284 139.25 37.9974 139.191 38.0726L139.047 38.3046L137.38 40.9069L136.915 41.7598C136.89 41.7765 136.873 41.8058 136.865 41.8476C136.86 41.8686 136.846 41.8874 136.821 41.9041C136.662 42.0461 136.525 42.2907 136.412 42.6378C136.374 42.7172 136.349 42.7883 136.336 42.8511C136.345 42.918 136.332 42.9808 136.298 43.0393L135.914 44.4634C135.855 44.6474 135.907 44.7123 136.07 44.6582C136.137 44.6499 136.242 44.6165 136.384 44.5581C136.811 44.383 137.144 44.1888 137.383 43.9758C137.467 43.8838 137.609 43.771 137.81 43.6374C138.174 43.3408 138.396 43.157 138.476 43.086C138.593 42.9355 138.742 42.7914 138.922 42.6535C139.123 42.5199 139.261 42.428 139.337 42.3779L139.883 41.9331C139.887 41.9121 139.902 41.8933 139.927 41.8766C139.957 41.839 139.975 41.8537 139.984 41.9206L140.021 41.8956L140.348 41.5697L140.807 41.0745C141.1 40.8071 141.398 40.4644 141.699 40.0464L142.749 38.7235L143.434 37.9148L143.711 37.5135L143.83 37.407L144.081 37.1312L144.301 36.8491L144.861 36.0151L145.138 35.6138C145.163 35.5971 145.165 35.5866 145.144 35.5824C145.148 35.5615 145.152 35.5406 145.157 35.5197L145.088 35.5384C145.037 35.5718 145.004 35.576 144.987 35.5509L145.038 35.4631C145.088 35.4297 145.125 35.4046 145.151 35.3879C145.201 35.3545 145.251 35.3211 145.301 35.2877C145.377 35.2376 145.473 35.1373 145.59 34.9868C145.662 34.8488 145.745 34.7569 145.842 34.711C145.875 34.6525 145.934 34.5772 146.018 34.4853C146.106 34.3724 146.16 34.2637 146.181 34.1592L146.194 34.0964C146.257 34.0003 146.322 33.8937 146.389 33.7766C146.46 33.6386 146.534 33.5446 146.609 33.4945C146.659 33.4611 146.739 33.3357 146.848 33.1182L147.414 31.9266L147.874 30.9419C148.067 30.5237 148.276 30.1851 148.502 29.926C148.561 29.8508 148.624 29.809 148.691 29.8007C148.754 29.8134 148.816 29.7716 148.879 29.6755L148.942 29.6881L148.936 29.7195C148.957 29.8324 149.009 29.8974 149.092 29.9142C149.134 29.9226 149.14 29.9456 149.111 29.9833C149.107 30.0042 149.103 30.0251 149.099 30.046C149.069 30.0836 149.023 30.1505 148.96 30.2467C148.922 30.3261 148.866 30.3909 148.79 30.441L148.746 30.4974C148.742 30.5183 148.734 30.5601 148.721 30.6229C148.713 30.6647 148.683 30.7023 148.633 30.7357L148.621 30.7985C148.671 30.8739 148.669 30.9387 148.614 30.993C148.585 31.0306 148.568 31.0599 148.564 31.0808L148.551 31.1436C148.534 31.2272 148.53 31.3025 148.538 31.3695C148.551 31.4155 148.563 31.4615 148.576 31.5076L148.613 31.4825C148.655 31.3822 148.71 31.2735 148.777 31.1564C148.869 31.0226 148.936 30.9056 148.978 30.8052C149.037 30.73 149.071 30.6714 149.079 30.6296L149.161 30.5481L149.142 30.6423C149.133 30.6841 149.163 30.7009 149.229 30.6926L149.261 30.6989C149.278 30.724 149.273 30.7449 149.248 30.7616C149.244 30.7825 149.252 30.7951 149.273 30.7993C149.294 30.8035 149.317 30.7973 149.342 30.7806C149.367 30.7639 149.382 30.7451 149.386 30.7241L149.393 30.6928C149.414 30.697 149.424 30.6991 149.424 30.6991C149.428 30.6782 149.43 30.6677 149.43 30.6677L149.455 30.7054L149.329 31.1697L149.31 31.2638C149.335 31.2471 149.358 31.2408 149.379 31.245C149.4 31.2492 149.413 31.2409 149.417 31.22L149.7 30.9505C149.721 30.9547 149.733 30.9463 149.738 30.9254L149.756 30.9945C149.748 31.0363 149.731 31.0656 149.706 31.0823L149.548 31.5402C149.536 31.6029 149.555 31.6176 149.605 31.5842C149.63 31.6763 149.638 31.7432 149.63 31.7851C149.626 31.806 149.619 31.8373 149.611 31.8792C149.607 31.9001 149.613 31.9231 149.63 31.9482L149.617 32.011L149.415 32.8517L149.39 32.9771L149.396 33.1089L149.509 33.0338L149.735 32.7203L149.779 32.6638L149.767 32.7266L149.672 33.034L149.622 33.1218L149.653 33.1281L149.672 33.034L149.961 32.7331L149.999 32.7081L149.986 32.7708L149.885 33.1096L149.873 33.1723L149.917 33.1159C149.938 33.1201 149.948 33.1222 149.948 33.1222C149.952 33.1013 149.954 33.0908 149.954 33.0908L150.011 33.1348L149.992 33.2289C149.715 33.9566 149.484 34.5085 149.299 34.8848C149.241 34.9601 149.205 35.0291 149.193 35.0918C149.184 35.1336 149.165 35.1734 149.136 35.211C149.119 35.2946 149.119 35.349 149.136 35.3741C149.169 35.4244 149.169 35.4788 149.135 35.5373L148.727 36.1079L148.683 36.1643L148.658 35.9634C148.645 35.9174 148.629 35.8923 148.608 35.8881C148.587 35.8839 148.564 35.8901 148.539 35.9068L148.218 36.2014C148.114 36.2891 148.015 36.3998 147.923 36.5336C147.856 36.6507 147.808 36.728 147.778 36.7656L147.709 36.7844L147.722 36.7216L147.747 36.5961C147.697 36.6295 147.668 36.6672 147.659 36.709L147.269 37.1854L147.232 37.2105L147.244 37.1478L147.288 37.0913L147.27 37.0223C147.265 37.0432 147.253 37.0515 147.232 37.0473L147.194 37.0724C147.19 37.0933 147.178 37.1017 147.157 37.0974L147.169 37.0347L147.264 36.8905C147.339 36.8404 147.358 36.8007 147.32 36.7713L147.289 36.6018L147.17 36.7084L146.881 37.0092C146.855 37.0259 146.841 37.0447 146.837 37.0657C146.832 37.0866 146.853 37.0908 146.899 37.0783L146.918 37.1473L146.761 37.2789C146.686 37.329 146.652 37.3876 146.66 37.4545L146.604 37.5737L145.937 38.4515C145.816 38.6228 145.68 38.813 145.529 39.022C145.382 39.2101 145.231 39.4191 145.076 39.649C144.887 39.9375 144.707 40.1841 144.535 40.3889C144.385 40.5979 144.25 40.7776 144.133 40.9281L144.095 40.9531C144.091 40.974 144.1 40.9866 144.12 40.9908C144.141 40.995 144.152 40.9971 144.152 40.9971C144.156 40.9762 144.158 40.9658 144.158 40.9658C144.493 40.598 144.736 40.3096 144.887 40.1006L145.07 39.8436C145.091 39.8478 145.103 39.8394 145.107 39.8185L145.095 39.8812L144.912 40.1383C144.795 40.2888 144.728 40.4058 144.711 40.4895C144.707 40.5104 144.661 40.5773 144.573 40.6902C144.489 40.7821 144.457 40.8846 144.478 40.9975L144.365 41.0727L144.151 41.3235C144.126 41.3402 144.107 41.3799 144.095 41.4426L144.214 41.3361L144.34 41.1982L144.478 40.9975C144.528 40.9641 144.556 40.937 144.56 40.9161C144.598 40.8366 144.656 40.7614 144.736 40.6904C144.82 40.5984 144.887 40.5357 144.937 40.5023L145.012 40.4522L145.044 40.4585L145.069 40.4962L144.937 40.6655L144.421 41.2799C144.224 41.5014 144.061 41.7187 143.931 41.9319C143.831 41.9987 143.803 42.0803 143.849 42.1766C143.866 42.2017 143.843 42.2079 143.78 42.1953C143.747 42.1451 143.703 42.1471 143.648 42.2014L143.334 42.6278C143.313 42.6236 143.3 42.6319 143.296 42.6528C143.313 42.678 143.319 42.701 143.315 42.7219L143.422 42.6781L143.428 42.6467L143.44 42.7471C143.428 42.8099 143.382 42.8768 143.302 42.9478C143.243 43.023 143.199 43.0795 143.17 43.1171L142.466 43.8567C142.433 43.9152 142.366 43.9779 142.265 44.0447L141.888 44.4584C141.813 44.5086 141.744 44.5273 141.681 44.5147C141.66 44.5105 141.637 44.5167 141.612 44.5334C141.587 44.5501 141.553 44.5542 141.512 44.5458L141.474 44.5709L141.518 44.5145L141.964 44.082C142.064 44.0152 142.134 43.9421 142.171 43.8626L142.184 43.7999L142.146 43.8249L141.757 44.1382C141.568 44.3179 141.445 44.4453 141.386 44.5206L141.153 44.8654C141.145 44.9073 141.103 44.9532 141.028 45.0033C140.919 45.112 140.843 45.2165 140.801 45.3168L140.757 45.3733L140.406 45.6615L139.978 45.9998L139.865 46.075C139.769 46.1209 139.681 46.1794 139.602 46.2504C139.543 46.3256 139.488 46.38 139.438 46.4134C139.371 46.5304 139.304 46.5931 139.237 46.6014C139.212 46.6181 139.206 46.6494 139.218 46.6955C139.101 46.7372 138.913 46.7537 138.653 46.745C138.632 46.7408 138.597 46.7554 138.547 46.7888L138.352 46.9454L137.46 47.484L137.322 47.5215C137.259 47.5088 137.18 47.5255 137.083 47.5714C136.991 47.5964 136.922 47.6151 136.876 47.6276C136.6 47.7025 136.387 47.7357 136.236 47.7272C136.211 47.7439 136.177 47.748 136.135 47.7396C136.115 47.7354 136.092 47.7416 136.066 47.7584C135.995 47.7875 135.916 47.8042 135.828 47.8083C135.74 47.8123 135.686 47.8123 135.665 47.808L135.37 47.8139L135.182 47.7761L134.818 47.6375ZM136.263 45.8069L136.377 45.7317L136.358 45.6626L136.213 45.7315L136.201 45.7942L136.263 45.8069ZM139.212 46.7269L139.218 46.6955L139.275 46.7395L139.231 46.7959L139.212 46.7269ZM138.48 44.5231L138.518 44.4981L138.675 44.3665L138.681 44.3351L138.493 44.4604L138.48 44.5231L138.367 44.5983L138.399 44.6046L138.48 44.5231ZM138.826 44.2663L138.807 44.1972L138.795 44.26L138.788 44.2913L138.826 44.2663ZM139.666 44.7945L139.641 44.7568L139.566 44.8069L139.622 44.8509L139.666 44.7945ZM139.046 44.1473L139.36 43.8841L139.366 43.8528L139.341 43.8151L139.31 43.8088L139.04 44.0155L138.952 44.1284L138.939 44.1911L139.046 44.1473ZM139.905 44.5814L139.754 44.6817L139.779 44.7193L139.905 44.5814ZM139.574 43.6334L139.548 43.5957L139.429 43.7022L139.486 43.7462L139.574 43.6334ZM140.213 44.3496L140.181 44.3433L140.112 44.3621C140.108 44.383 140.106 44.3934 140.106 44.3934C140.127 44.3976 140.137 44.3997 140.137 44.3997L140.213 44.3496ZM139.75 43.0813L139.756 43.05L139.694 43.0373L139.681 43.1001L139.675 43.1315L139.75 43.0813ZM139.875 43.1066L139.882 43.0752L139.806 43.1253L139.8 43.1567L139.875 43.1066ZM139.957 43.3515L140.158 43.1634L140.164 43.1321C140.164 43.1321 140.154 43.13 140.133 43.1258C140.137 43.1048 140.137 43.1048 140.133 43.1258L139.9 43.3075L139.894 43.3388L139.957 43.3515ZM140.289 43.3205L140.214 43.3706L140.289 43.3205ZM140.152 42.7053C140.156 42.6844 140.148 42.6718 140.127 42.6676L140.001 42.8055L140.152 42.7053ZM138.009 40.0542L138.022 39.9915L138.053 39.9978C138.12 39.9895 138.183 39.9478 138.242 39.8725C138.321 39.8015 138.386 39.7493 138.436 39.7159C138.357 39.8957 138.269 40.0085 138.172 40.0544L138.066 40.0982L138.009 40.0542ZM139.695 42.2215L139.814 42.115L139.669 42.1838L139.663 42.2152L139.657 42.2466L139.695 42.2215ZM140.566 42.756L140.51 42.712L140.415 42.8563L140.441 42.894L140.566 42.756ZM140.923 43.7418C140.973 43.7084 141 43.6812 141.004 43.6603L141.067 43.5098C141.109 43.5182 141.132 43.5119 141.136 43.491L141.143 43.4597C141.143 43.4597 141.132 43.4576 141.111 43.4533C141.111 43.4533 141.109 43.4638 141.105 43.4847L141.099 43.5161C140.998 43.5829 140.933 43.6351 140.904 43.6727L140.923 43.7418ZM138.562 39.4148L138.6 39.3898L138.587 39.4525L138.436 39.7159L138.562 39.4148ZM140.648 42.6746C140.661 42.6118 140.726 42.5052 140.843 42.3548L140.811 42.3484L140.598 42.5992L140.61 42.6996L140.648 42.6746ZM140.523 41.9966C140.527 41.9757 140.509 41.961 140.467 41.9526L140.335 42.1219L140.523 41.9966ZM140.655 41.8274L140.636 41.7583L140.592 41.8147C140.588 41.8356 140.586 41.8461 140.586 41.8461C140.607 41.8503 140.618 41.8524 140.618 41.8524L140.655 41.8274ZM141.645 43.0712C141.624 43.067 141.616 43.0544 141.62 43.0335L141.545 43.0836L141.57 43.1213L141.645 43.0712ZM138.902 38.863C138.906 38.8421 138.929 38.8358 138.971 38.8442L138.902 38.863ZM142.448 43.6245C142.452 43.6036 142.444 43.591 142.423 43.5868L142.259 43.7498L142.291 43.7561L142.448 43.6245ZM141.859 42.8204L141.941 42.739L141.953 42.6762L141.859 42.6573L141.765 42.8015L141.752 42.8642L141.859 42.8204ZM140.907 41.5515L141.158 41.2757L141.164 41.2444C141.014 41.3446 140.928 41.447 140.907 41.5515L140.831 41.6017L140.825 41.633L140.907 41.5515ZM142.104 42.576C142.117 42.5133 142.135 42.4735 142.161 42.4568C142.19 42.4192 142.219 42.3816 142.249 42.344L142.299 42.2562C142.303 42.2353 142.295 42.2227 142.274 42.2185L142.022 42.4943L142.029 42.6261L142.104 42.576ZM141.365 41.0563L141.378 40.9936L141.309 41.0123L141.252 41.1315L141.365 41.0563ZM141.78 40.6176L141.755 40.5799L141.724 40.5736C141.673 40.607 141.615 40.6822 141.548 40.7993L141.579 40.8056L141.78 40.6176ZM142.714 41.8174C142.73 41.8425 142.745 41.8237 142.758 41.761L142.802 41.7046L142.852 41.6168C142.789 41.6041 142.745 41.6062 142.72 41.6229C142.699 41.6187 142.68 41.6584 142.664 41.742C142.664 41.742 142.661 41.7525 142.657 41.7734C142.674 41.7985 142.693 41.8132 142.714 41.8174ZM143.472 42.5903L143.503 42.5966L143.428 42.6467L143.459 42.653L143.397 42.6404L143.472 42.5903ZM142.006 40.3041L141.975 40.2978L141.937 40.3228C141.937 40.3228 141.935 40.3333 141.931 40.3542C141.931 40.3542 141.942 40.3563 141.962 40.3605L142.006 40.3041ZM142.602 40.4241C142.619 40.3404 142.642 40.2798 142.672 40.2422C142.735 40.2548 142.772 40.2297 142.785 40.167L142.76 40.1293C142.71 40.1627 142.684 40.1794 142.684 40.1794L142.672 40.2422C142.609 40.2295 142.573 40.2441 142.565 40.286C142.552 40.3487 142.552 40.4031 142.565 40.4491L142.602 40.4241ZM143.053 41.4288C143.057 41.4078 143.059 41.3974 143.059 41.3974C143.08 41.4016 143.091 41.4037 143.091 41.4037L143.273 41.1466C143.298 41.1299 143.3 41.1195 143.279 41.1153C143.284 41.0943 143.288 41.0734 143.292 41.0525C143.338 41.04 143.378 41.0045 143.411 40.946C143.466 40.8917 143.518 40.8478 143.568 40.8144L143.581 40.7516L143.512 40.7704L143.292 41.0525L143.034 41.3597L143.053 41.4288ZM142.547 39.7274L142.49 39.6834L142.446 39.7398C142.426 39.7356 142.413 39.744 142.409 39.7649C142.43 39.7691 142.44 39.7712 142.44 39.7712L142.547 39.7274ZM143.043 39.8598C143.089 39.8473 143.126 39.8223 143.156 39.7846C143.189 39.7261 143.208 39.6864 143.212 39.6655L143.244 39.6718C143.311 39.6635 143.327 39.6342 143.294 39.584L143.269 39.5463C143.227 39.5379 143.21 39.5672 143.219 39.6341L143.212 39.6655L143.143 39.6842L142.986 39.8158C142.982 39.8367 143.001 39.8514 143.043 39.8598ZM143.125 38.9625L143.251 38.8246L143.257 38.7932L143.226 38.7869C143.167 38.8621 143.134 38.9207 143.125 38.9625C142.983 39.0209 142.889 39.1107 142.842 39.232C142.842 39.232 142.84 39.2424 142.836 39.2634C142.836 39.2634 142.847 39.2655 142.868 39.2697L143.125 38.9625ZM143.363 39.4021L143.351 39.3017L143.275 39.3518C143.309 39.402 143.323 39.4376 143.319 39.4585L143.363 39.4021ZM143.682 40.7392C143.698 40.6556 143.74 40.6096 143.807 40.6013L143.814 40.5699C143.83 40.4863 143.866 40.4173 143.92 40.363C143.975 40.3087 144.017 40.2627 144.046 40.2251L144.335 39.9242L144.386 39.8364L144.367 39.7674L144.298 39.7861L144.203 39.9303C144.178 39.947 144.149 39.9846 144.115 40.0432C144.086 40.0808 144.048 40.1058 144.002 40.1183C143.956 40.1308 143.917 40.1663 143.883 40.2249C143.875 40.2667 143.868 40.2981 143.864 40.319L143.644 40.6011C143.61 40.6596 143.623 40.7057 143.682 40.7392ZM143.483 39.2956C143.508 39.2789 143.51 39.2684 143.489 39.2642C143.493 39.2433 143.497 39.2224 143.501 39.2014C143.585 39.2183 143.612 39.1911 143.583 39.12L143.552 39.1136C143.527 39.1304 143.51 39.1596 143.501 39.2014L143.451 39.2892L143.445 39.3206L143.483 39.2956ZM143.383 38.6553C143.404 38.6595 143.419 38.6407 143.427 38.5989L143.685 38.2917C143.827 38.1245 143.947 37.9636 144.043 37.8089L144.087 37.7525C144.045 37.7441 144.024 37.7399 144.024 37.7399L143.949 37.79L143.333 38.5799L143.327 38.6113L143.314 38.674L143.383 38.6553ZM143.966 38.838L144.054 38.7252C144.059 38.7043 144.073 38.6855 144.098 38.6688C144.149 38.6354 144.157 38.5935 144.124 38.5433L144.061 38.5307C144.006 38.585 144.004 38.6498 144.054 38.7252L143.941 38.8004C143.916 38.8171 143.901 38.8359 143.897 38.8568C143.918 38.861 143.929 38.8631 143.929 38.8631L143.966 38.838ZM144.971 38.7138L144.939 38.7075L144.726 38.9582L144.744 39.0273L144.971 38.7138ZM145.541 39.2856L145.535 39.317C145.476 39.3922 145.422 39.4465 145.371 39.48L145.541 39.2856ZM144.219 37.5832C144.244 37.5665 144.263 37.5268 144.276 37.4641C144.225 37.4975 144.194 37.5455 144.181 37.6083L144.219 37.5832ZM144.426 37.3638C144.368 37.3303 144.339 37.3135 144.339 37.3135L144.301 37.3386L144.357 37.3826L144.426 37.3638ZM144.865 37.6154C144.844 37.6112 144.834 37.6091 144.834 37.6091C144.838 37.5882 144.84 37.5777 144.84 37.5777L144.765 37.6278C144.765 37.6278 144.763 37.6383 144.759 37.6592C144.759 37.6592 144.769 37.6613 144.79 37.6655L144.865 37.6154ZM144.621 37.044C144.642 37.0482 144.642 37.0482 144.621 37.044C144.626 37.0231 144.628 37.0126 144.628 37.0126C144.565 37 144.527 37.0251 144.515 37.0878L144.533 37.1569L144.621 37.044ZM144.411 39.7109C144.453 39.7194 144.476 39.7131 144.48 39.6922L144.87 39.2157L145.046 38.99C145.046 38.99 145.127 38.9086 145.291 38.7456C145.337 38.6243 145.412 38.5198 145.517 38.4321C145.731 38.2357 145.879 38.0372 145.963 37.8365L146.007 37.78L146.347 37.3914L146.498 37.128L146.485 37.0276C146.435 37.061 146.41 37.0777 146.41 37.0777L146.108 37.4413C146.045 37.5374 145.957 37.6503 145.844 37.7798C145.752 37.9136 145.645 38.0662 145.523 38.2376L144.7 39.2469L144.423 39.6482C144.423 39.6482 144.419 39.6691 144.411 39.7109ZM144.872 37.4209L144.815 37.3769L144.778 37.4019L144.803 37.4396L144.872 37.4209ZM145.11 37.371C145.077 37.3207 145.06 37.2956 145.06 37.2956L145.016 37.352L145.041 37.3897L145.11 37.371ZM144.866 36.7996C144.871 36.7787 144.883 36.7703 144.904 36.7745L144.879 36.7368C144.804 36.7869 144.749 36.8413 144.716 36.8998L144.866 36.7996ZM145.104 37.076L145.111 37.0446L144.991 37.1512L145.048 37.1952L145.104 37.076ZM145.243 36.8754L145.249 36.844L145.205 36.9004L145.236 36.9067L145.243 36.8754ZM144.986 36.5299C145.028 36.5383 145.051 36.532 145.055 36.5111L145.225 36.3168L145.206 36.2477L145.162 36.3042C145.112 36.3376 145.057 36.3919 144.999 36.4671L144.986 36.5299ZM145.651 36.6311C145.634 36.606 145.605 36.5892 145.563 36.5808C145.542 36.5766 145.524 36.5619 145.507 36.5368L145.431 36.5869C145.465 36.6372 145.482 36.6623 145.482 36.6623L145.569 36.7126L145.632 36.7252L145.651 36.6311ZM145.877 36.9703C145.843 36.9201 145.826 36.8949 145.826 36.8949L145.738 37.0078C145.734 37.0287 145.732 37.0392 145.732 37.0392C145.753 37.0434 145.763 37.0455 145.763 37.0455L145.877 36.9703ZM145.319 36.1726C145.353 36.114 145.399 36.0472 145.457 35.9719C145.537 35.9009 145.583 35.834 145.596 35.7713C145.667 35.7421 145.707 35.7066 145.715 35.6647L145.69 35.6271C145.598 35.652 145.566 35.7001 145.596 35.7713C145.52 35.8214 145.48 35.8569 145.476 35.8778L145.263 36.1286C145.258 36.1495 145.256 36.1599 145.256 36.1599C145.277 36.1642 145.288 36.1663 145.288 36.1663L145.319 36.1726ZM145.789 36.4305C145.814 36.4138 145.838 36.4075 145.858 36.4117C145.879 36.416 145.904 36.3992 145.934 36.3616C145.955 36.3658 145.957 36.3554 145.94 36.3303C145.944 36.3093 145.949 36.2884 145.953 36.2675L145.884 36.2863L145.758 36.4242L145.746 36.3237C145.75 36.3028 145.741 36.2903 145.721 36.2861L145.714 36.3174L145.789 36.4305ZM146.078 36.1296L146.053 36.0919L146.016 36.117L146.009 36.1484L146.078 36.1296ZM146.223 36.0608C146.223 36.0608 146.206 36.0356 146.173 35.9854L146.135 36.0104L146.154 36.0795L146.223 36.0608ZM146.21 36.4498C146.26 36.4164 146.285 36.3997 146.285 36.3997L146.38 36.0923L146.411 36.0987L146.48 36.0799L146.455 36.0422L146.386 36.061L146.38 36.0923C146.271 36.201 146.208 36.2971 146.191 36.3808L146.21 36.4498ZM146.981 37.3231C146.993 37.2604 147.033 37.2249 147.1 37.2166L147.012 37.3295C147.008 37.3504 146.995 37.3587 146.974 37.3545C146.974 37.3545 146.976 37.3441 146.981 37.3231ZM146.129 35.7155L146.11 35.6464L146.098 35.7092L146.129 35.7155ZM145.878 35.5018L146.186 35.1068L146.287 34.9312L146.224 34.9186L146.048 35.1443L145.791 35.4515L145.772 35.5456L145.878 35.5018ZM146.574 35.9357L146.549 35.898L146.48 35.9168L146.499 35.9858L146.574 35.9357ZM146.819 36.0176L146.756 36.005L146.744 36.0677L146.769 36.1054L146.819 36.0176ZM146.706 35.7664C146.728 35.6619 146.763 35.5929 146.813 35.5595L146.901 35.4466L146.914 35.3839L146.845 35.4026C146.774 35.4318 146.717 35.4966 146.675 35.5969C146.638 35.6764 146.617 35.7266 146.612 35.7475L146.631 35.8165L146.706 35.7664ZM146.576 34.9567L146.544 34.9504L146.349 35.2702L146.406 35.3142L146.576 34.9567ZM147.189 35.9616L147.158 35.9553L147.07 36.0681L147.064 36.0995L147.189 35.9616ZM146.242 35.8035C146.238 35.8244 146.246 35.837 146.267 35.8412C146.292 35.8245 146.305 35.8161 146.305 35.8161C146.372 35.8078 146.439 35.7452 146.506 35.6281L146.619 35.3898C146.657 35.3103 146.793 35.0657 147.028 34.656L147.185 34.3613L147.198 34.2985L147.16 34.3236L146.928 34.6685L146.418 35.4146C146.389 35.4522 146.345 35.4543 146.286 35.4207C146.261 35.4374 146.234 35.4646 146.205 35.5022C146.18 35.5189 146.175 35.5398 146.192 35.5649C146.251 35.5985 146.265 35.6341 146.236 35.6717C146.227 35.7135 146.223 35.7344 146.223 35.7344C146.215 35.7763 146.221 35.7993 146.242 35.8035ZM147.196 35.767C147.196 35.767 147.186 35.7649 147.165 35.7607C147.165 35.7607 147.167 35.7503 147.171 35.7294L147.165 35.7607C147.139 35.7774 147.127 35.7858 147.127 35.7858C147.148 35.79 147.158 35.7921 147.158 35.7921L147.196 35.767ZM147.027 35.3087L146.952 35.1956L146.914 35.2207L147.021 35.3401L147.027 35.3087ZM146.439 34.1783L146.451 34.1156L146.407 34.172L146.363 34.2284C146.359 34.2493 146.367 34.2619 146.388 34.2661L146.439 34.1783ZM147.071 35.0891C147.18 34.9805 147.243 34.8843 147.26 34.8007C147.327 34.6836 147.373 34.6167 147.398 34.6C147.428 34.5624 147.413 34.5268 147.354 34.4933L147.279 34.5434L147.254 34.6689L147.015 35.0451C147.015 35.0451 147.013 35.0556 147.009 35.0765C147.009 35.0765 147.019 35.0786 147.04 35.0828L147.071 35.0891ZM147.154 34.0286C147.158 34.0077 147.15 33.9951 147.129 33.9909L147.098 33.9846L147.117 34.0537L147.154 34.0286ZM148.651 36.158L148.683 36.1643L148.689 36.1329L148.683 36.1643C148.649 36.2228 148.612 36.2479 148.57 36.2395L148.651 36.158ZM147.468 34.4181C147.518 34.3847 147.543 34.368 147.543 34.368C147.568 34.3513 147.56 34.3387 147.518 34.3303C147.476 34.3219 147.457 34.3072 147.461 34.2863L147.424 34.3114C147.457 34.3616 147.472 34.3972 147.468 34.4181ZM147.073 33.7838L147.205 33.6145L147.18 33.5768L147.149 33.5705L147.042 33.7774C147.042 33.7774 147.039 33.7879 147.035 33.8088L147.073 33.7838ZM147.399 33.9473L147.374 33.9097L147.361 33.9724C147.361 33.9724 147.359 33.9829 147.355 34.0038C147.355 34.0038 147.366 34.0059 147.386 34.0101L147.399 33.9473ZM147.467 35.0708C147.467 35.0708 147.477 35.0729 147.498 35.0771C147.523 35.0604 147.538 35.0416 147.542 35.0207L147.831 34.5566C147.861 34.519 147.884 34.4584 147.901 34.3747C147.917 34.2911 147.938 34.2409 147.964 34.2242C148.01 34.2117 148.064 34.1574 148.127 34.0612L148.272 33.666C148.238 33.6158 148.222 33.5907 148.222 33.5907C148.18 33.5823 148.144 33.5968 148.115 33.6345C148.077 33.7139 148.033 33.8247 147.983 33.9669C147.957 34.0924 147.915 34.1928 147.857 34.268C147.827 34.3056 147.794 34.3641 147.756 34.4436C147.718 34.523 147.695 34.5837 147.687 34.6255L147.605 34.707L147.454 34.9704C147.446 35.0122 147.45 35.0457 147.467 35.0708ZM147.618 34.1547C147.64 34.0502 147.705 33.9435 147.813 33.8349L147.832 33.7408C147.807 33.7575 147.774 33.7616 147.732 33.7532L147.537 34.073C147.554 34.0982 147.558 34.1316 147.549 34.1735L147.618 34.1547ZM147.274 33.4326C147.299 33.4159 147.318 33.3761 147.331 33.3134L147.331 32.9871C147.394 32.9997 147.434 32.9642 147.451 32.8805L147.432 32.8115C147.382 32.8449 147.357 32.8616 147.357 32.8616L147.331 32.9871C147.323 33.0289 147.291 33.077 147.237 33.1313C147.203 33.1898 147.193 33.2421 147.205 33.2881L147.124 33.3696L147.117 33.401C147.163 33.3885 147.189 33.3718 147.193 33.3509C147.201 33.3091 147.208 33.2777 147.212 33.2568C147.27 33.2903 147.27 33.3447 147.212 33.4199L147.237 33.4576L147.274 33.4326ZM147.544 33.7153C147.573 33.6777 147.638 33.5711 147.739 33.3955L147.915 33.0066L147.928 32.9439L147.89 32.969L147.695 33.2888L147.519 33.6776L147.506 33.7404L147.544 33.7153ZM147.87 33.5526C147.912 33.561 147.935 33.5547 147.939 33.5338L148.04 33.3582C148.04 33.3582 148.074 33.2997 148.141 33.1826L148.072 33.2014C148.005 33.2097 147.952 33.2535 147.914 33.333C147.898 33.4166 147.885 33.4794 147.877 33.5212L147.87 33.5526ZM149.199 35.2236L149.243 35.1672L149.268 35.2049L149.224 35.2613L149.199 35.2236ZM147.689 32.6675C147.706 32.6926 147.714 32.7051 147.714 32.7051C147.74 32.6884 147.763 32.6822 147.784 32.6864L147.708 32.5734L147.664 32.6298L147.689 32.6675ZM148.341 33.4841L148.536 33.1643L148.517 33.0953L148.48 33.1203C148.45 33.1579 148.419 33.206 148.385 33.2645C148.373 33.3273 148.333 33.3628 148.266 33.3711L148.303 33.5092L148.341 33.4841ZM148.38 32.6432L148.399 32.5491L148.411 32.4864L148.336 32.5365L148.317 32.6306L148.311 32.662L148.38 32.6432ZM147.797 31.6447L147.772 31.607L147.735 31.632C147.73 31.6529 147.726 31.6739 147.722 31.6948C147.743 31.699 147.756 31.6906 147.76 31.6697L147.797 31.6447ZM147.551 32.7049C147.551 32.7049 147.556 32.684 147.564 32.6422L147.702 32.4416C147.757 32.496 147.792 32.4814 147.809 32.3978C147.843 32.3392 147.893 32.2514 147.96 32.1344C148.027 32.0173 148.05 31.9023 148.029 31.7893L148.042 31.7266L148.262 31.4444C148.371 31.3358 148.423 31.2375 148.419 31.1497L148.451 30.9928L148.489 30.9678L148.564 30.9176L148.539 30.88L148.457 30.9614L148.451 30.9928L148.325 31.1307L147.835 31.9459C147.742 32.0797 147.621 32.3055 147.47 32.6233L147.457 32.686L147.476 32.7551L147.551 32.7049ZM149.741 33.5047C149.745 33.4838 149.736 33.4713 149.715 33.4671L149.703 33.5298L149.697 33.5612L149.741 33.5047ZM149.928 29.4948C149.932 29.4739 149.934 29.4634 149.934 29.4634C149.955 29.4676 149.965 29.4697 149.965 29.4697L150.141 29.244C150.2 29.1688 150.252 29.1249 150.298 29.1124L150.518 28.9935C150.568 28.9601 150.625 28.9497 150.688 28.9623C150.587 29.0291 150.537 29.0625 150.537 29.0625C150.503 29.1211 150.436 29.1837 150.336 29.2506C150.256 29.3216 150.191 29.3738 150.141 29.4072C150.116 29.4239 150.043 29.4636 149.921 29.5262L149.928 29.4948ZM31.2394 52.9312C31.2603 52.9354 31.2728 52.927 31.277 52.9061L31.3461 52.8874L31.4905 52.8185L31.6663 52.756C31.6872 52.7602 31.7228 52.7456 31.7731 52.7122L31.9489 52.6497L31.9866 52.6246L31.9238 52.612L31.7731 52.7122L31.6413 52.7183L31.5659 52.7684L31.5345 52.7621C31.4718 52.7495 31.4362 52.7641 31.4278 52.8059C31.4236 52.8268 31.411 52.8352 31.3901 52.831L31.2396 52.768C31.1977 52.7596 31.1852 52.7679 31.2019 52.7931L31.1516 52.8809L31.1328 52.8118L31.0701 52.7992L30.932 52.8367C30.932 52.8367 30.9215 52.8345 30.9006 52.8303C30.8755 52.847 30.8567 52.8324 30.8442 52.7863C30.8442 52.7863 30.8233 52.7821 30.7814 52.7737C30.7605 52.7695 30.7375 52.7757 30.7124 52.7924C30.6788 52.851 30.637 52.8426 30.5869 52.7672L30.3987 52.7293L30.3673 52.723L30.3736 52.6916L30.3799 52.6602L30.3486 52.6539L30.2795 52.6727L30.2418 52.6977C30.2418 52.6977 30.2251 52.6726 30.1917 52.6223L30.2294 52.5973L30.2985 52.5785L30.3425 52.5221L30.2797 52.5095C30.2588 52.5053 30.2274 52.499 30.1856 52.4905C30.1647 52.4863 30.1521 52.4947 30.1479 52.5156C30.1437 52.5365 30.1311 52.5449 30.1102 52.5407L30.1165 52.5093L30.0727 52.4025C30.0727 52.4025 30.0476 52.4192 29.9974 52.4526C29.989 52.4945 29.9743 52.5133 29.9534 52.5091C29.8697 52.4922 29.8321 52.4629 29.8405 52.4211C29.8322 52.3541 29.8072 52.3164 29.7654 52.308C29.7444 52.3038 29.7361 52.2912 29.7403 52.2703L29.7656 52.1448C29.7949 52.1072 29.7908 52.0738 29.7531 52.0444C29.7364 52.0193 29.7176 52.0046 29.6967 52.0004C29.6549 51.992 29.6194 51.9522 29.5902 51.881C29.4982 51.7972 29.4188 51.7595 29.3518 51.7678L29.2891 51.7551L29.3331 51.6987C29.3834 51.6653 29.3792 51.6318 29.3207 51.5983L29.2015 51.5417C29.1221 51.5039 29.0656 51.5143 29.032 51.5728C29.032 51.5728 29.0069 51.5895 28.9567 51.6229L28.9379 51.5539C28.9506 51.4911 28.9673 51.4619 28.9882 51.4661C29.0636 51.416 29.116 51.3177 29.1455 51.1713L29.3344 50.7197C29.393 50.6445 29.4266 50.5859 29.435 50.5441C29.4643 50.5065 29.4853 50.4563 29.4979 50.3936L29.5419 50.3372L29.6489 50.1302L29.6929 50.0738L29.7998 49.8668L29.7685 49.8605L29.6805 49.9733L29.7057 49.8479L29.8127 49.6409L29.9828 49.1202C29.9996 49.0366 30.0667 48.9195 30.1841 48.769C30.2134 48.7314 30.2448 48.6833 30.2784 48.6248C30.3161 48.5454 30.3392 48.4847 30.3476 48.4429L30.5552 48.0604L31.1902 47.1763L31.5422 46.7249L32.0012 46.0665L32.6989 45.1951L32.8309 45.0258C32.8896 44.9506 32.9148 44.8795 32.9065 44.8125C32.8857 44.6995 32.8754 44.5343 32.8757 44.3167C32.9094 44.1494 32.9535 44.0386 33.0079 43.9842C33.0415 43.9257 33.075 43.8672 33.1086 43.8087C33.1463 43.7292 33.1945 43.6519 33.2532 43.5766L33.3412 43.4638C33.4668 43.3803 33.5506 43.2883 33.5926 43.188C33.6722 43.117 33.8082 43.0355 34.0008 42.9437C34.0929 42.9188 34.2352 42.8604 34.4278 42.7686C34.5283 42.7018 34.6476 42.6496 34.7857 42.6121C34.8066 42.6163 34.8422 42.6017 34.8925 42.5683L35.6906 41.6845L36.1243 41.1516C36.2835 41.0095 36.384 40.8883 36.426 40.788C36.4889 40.6918 36.5496 40.6061 36.6083 40.5309C36.6921 40.439 36.7612 40.3658 36.8157 40.3115L37.3184 39.7599C37.4107 39.6261 37.5238 39.4966 37.6578 39.3712C37.8925 39.0703 38.0602 38.832 38.1608 38.6564C38.2279 38.5394 38.2866 38.4641 38.3368 38.4307L38.4814 38.1987L38.7391 37.8915C38.7433 37.8706 38.7559 37.8623 38.7768 37.8665C38.735 37.8581 38.7141 37.8538 38.7141 37.8538C38.3626 37.8701 38.0948 37.9033 37.9107 37.9532C37.8646 37.9657 37.8269 37.9908 37.7976 38.0284C37.7934 38.0493 37.7871 38.0807 37.7787 38.1225L37.7347 38.1789C37.6635 38.2081 37.6133 38.1872 37.5841 38.116C37.5716 38.07 37.5591 38.0239 37.5466 37.9779C37.5384 37.9109 37.5092 37.8398 37.4591 37.7644C37.4423 37.7393 37.4361 37.7162 37.4403 37.6953C37.4654 37.6786 37.4801 37.6598 37.4843 37.6389C37.4969 37.5762 37.4802 37.551 37.4342 37.5635L37.227 37.6198C37.2228 37.6407 37.2103 37.649 37.1893 37.6448C37.1893 37.6448 37.1915 37.6344 37.1957 37.6134L37.1643 37.6071L37.158 37.6385L37.1453 37.7012L37.1203 37.6635C37.1036 37.6384 37.0743 37.6217 37.0325 37.6132C37.0116 37.609 36.9551 37.6194 36.863 37.6444C36.8212 37.636 36.817 37.6569 36.8504 37.7071L36.8377 37.7699L36.8064 37.7636C36.7521 37.7091 36.6663 37.7027 36.5491 37.7444C36.457 37.7694 36.4089 37.738 36.4049 37.6501C36.3966 37.5831 36.3715 37.5455 36.3297 37.537C36.3005 37.4659 36.2985 37.4219 36.3236 37.4052C36.3362 37.3425 36.3258 37.286 36.2924 37.2357C36.2842 37.1688 36.3009 37.1395 36.3428 37.148C36.3428 37.148 36.3679 37.1312 36.4181 37.0978C36.3763 37.0894 36.347 37.0726 36.3303 37.0475L36.299 37.0412C36.2362 37.0286 36.23 37.0056 36.2802 36.9722L36.2929 36.9094L36.3745 36.8279L36.3809 36.7966L36.3495 36.7902C36.3244 36.8069 36.3035 36.8027 36.2867 36.7776C36.291 36.7567 36.3056 36.7379 36.3307 36.7212L36.3811 36.6334L36.4691 36.5205L36.5131 36.4641L36.9777 36.2639C37.3335 36.1179 37.7667 36.0201 38.2772 35.9706C38.7877 35.921 39.0973 35.8963 39.2061 35.8964C39.3191 35.8757 39.5053 35.8696 39.7646 35.8783C39.8776 35.8576 40.0638 35.8515 40.3232 35.8602C40.8211 35.8734 41.1662 35.8885 41.3586 35.9055L42.0364 35.944C42.2037 35.9777 42.3229 35.9799 42.3941 35.9507C42.4777 35.9675 42.5384 35.9906 42.576 36.02C42.7224 36.0494 42.8312 36.0496 42.9023 36.0204C42.9274 36.0037 42.9923 36.0059 43.0969 36.0269L43.4293 36.1591L43.5798 36.2221C43.6593 36.2598 43.7158 36.2494 43.7493 36.1909L43.8184 36.1722C43.8936 36.2308 43.9626 36.2665 44.0253 36.2791L44.0441 36.3482L44.0127 36.3419L43.8182 36.3353C43.7973 36.3311 43.7659 36.3248 43.7241 36.3164C43.7074 36.2913 43.6843 36.2975 43.655 36.3351C43.6508 36.356 43.6173 36.3602 43.5546 36.3476C43.4082 36.3181 43.3015 36.3075 43.2346 36.3158L43.1718 36.3031L43.2282 36.3471C43.3746 36.3766 43.5294 36.4186 43.6925 36.4732C43.8807 36.5111 44.0397 36.5323 44.1694 36.5366C44.2739 36.5577 44.4057 36.6059 44.5645 36.6814L45.0035 36.933C45.0077 36.9121 45.0203 36.9038 45.0412 36.908L45.1103 36.8892L45.2545 36.9836C45.3046 37.0589 45.336 37.0652 45.3486 37.0025L45.38 37.0088C45.4636 37.0257 45.5243 37.0488 45.5619 37.0781L45.9632 37.3547C45.9841 37.3589 46.0322 37.3904 46.1074 37.449C46.2956 37.4869 46.4503 37.5834 46.5714 37.7383C46.6048 37.7886 46.6592 37.843 46.7344 37.9017C46.8263 37.9855 46.8785 38.1048 46.8908 38.2596C46.8907 38.3684 46.9114 38.5358 46.953 38.7617C46.9862 38.9208 46.986 39.0839 46.9523 39.2513C46.9313 39.3558 46.8872 39.4666 46.8201 39.5837C46.753 39.7008 46.7027 39.7886 46.6692 39.8471C46.5434 40.0394 46.4386 40.1815 46.3548 40.2734L46.0531 40.637L45.8207 40.8187L45.4626 41.1384C44.8301 41.6856 44.5411 41.9321 44.5956 41.8778L44.3381 42.0218C44.3381 42.0218 44.2879 42.0552 44.1874 42.122C44.0617 42.2055 43.9989 42.2473 43.9989 42.2473L43.9549 42.3037L43.9863 42.31L43.9486 42.3351L43.6471 42.5355L43.0001 42.9928L42.3784 43.3247L41.9702 43.5689C41.9702 43.5689 41.8823 43.6274 41.7064 43.7443C41.6059 43.8111 41.5326 43.8507 41.4866 43.8632C41.4406 43.8757 41.3924 43.8987 41.3422 43.9321C41.3128 43.9697 41.2647 43.9927 41.1977 44.0009C41.1726 44.0176 41.091 44.0447 40.9529 44.0822C40.7938 44.1155 40.6682 44.199 40.576 44.3328C40.5509 44.3495 40.4797 44.3787 40.3625 44.4203L40.2872 44.4705C40.2829 44.4914 40.3018 44.506 40.3436 44.5145C40.423 44.5522 40.5652 44.6026 40.7701 44.6656C40.9751 44.7286 41.1318 44.8146 41.2405 44.9235L41.5287 45.2753L41.7167 45.4764C41.8087 45.5602 41.911 45.7005 42.0237 45.8973L42.268 46.3055C42.343 46.4729 42.3722 46.5985 42.3553 46.6821C42.3511 46.7031 42.3553 46.7365 42.3678 46.7826C42.3802 46.8286 42.3739 46.86 42.3488 46.8767C42.3446 46.8976 42.332 46.9059 42.3111 46.9017L42.3048 46.9331C42.3173 46.9791 42.3172 47.0335 42.3046 47.0963C42.2962 47.1381 42.2982 47.182 42.3107 47.2281C42.3274 47.2532 42.3211 47.2846 42.2918 47.3222C42.2876 47.3431 42.2833 47.364 42.2791 47.3849C42.2707 47.4268 42.2476 47.4874 42.2099 47.5668C42.1763 47.6254 42.1637 47.6881 42.172 47.7551L42.1657 47.7864C42.0903 47.8365 42.0755 47.9097 42.1214 48.006L42.0901 47.9997C41.9938 48.0456 41.956 48.125 41.9768 48.238L42.0019 48.2757C41.981 48.2715 41.9391 48.3175 41.8762 48.4136C41.872 48.4345 41.8573 48.4534 41.8322 48.4701C41.807 48.4868 41.7903 48.516 41.7819 48.5579C41.7609 48.5536 41.7484 48.562 41.7442 48.5829C41.7651 48.5871 41.7755 48.5892 41.7755 48.5892C41.7965 48.5934 41.8048 48.606 41.8006 48.6269C41.7964 48.6478 41.8026 48.6708 41.8193 48.696L41.7566 48.6833L41.7252 48.677C41.7419 48.7021 41.7273 48.721 41.6812 48.7334C41.6603 48.7292 41.6477 48.7376 41.6435 48.7585C41.6602 48.7836 41.6665 48.8066 41.6623 48.8276C41.6581 48.8485 41.6643 48.8715 41.681 48.8966L41.7124 48.9029C41.8548 48.7358 41.9303 48.6313 41.9387 48.5894C41.9974 48.5142 42.0456 48.4369 42.0833 48.3574C42.1211 48.278 42.1442 48.2173 42.1526 48.1755L42.3288 47.7866L42.373 47.567L42.3358 47.2658L42.3484 47.203C42.3693 47.2072 42.3777 47.2198 42.3734 47.2407L42.4297 47.4479C42.417 47.5106 42.44 47.5588 42.4985 47.5923C42.5194 47.5965 42.5257 47.6195 42.5173 47.6614C42.513 47.6823 42.5193 47.7053 42.536 47.7304L42.561 47.7681C42.628 47.7598 42.6531 47.7975 42.6362 47.8812C42.6278 47.923 42.6194 47.9648 42.611 48.0066C42.6234 48.0527 42.6129 48.105 42.5794 48.1635L42.359 48.772C42.3086 48.9141 42.1912 49.119 42.0067 49.3865C41.7972 49.6708 41.4663 49.9632 41.014 50.2639C40.6874 50.481 40.2834 50.7043 39.802 50.9338L39.2243 51.2092C39.128 51.2551 38.9878 51.3031 38.8036 51.353C38.7367 51.3613 38.6529 51.3989 38.5524 51.4657L38.1695 51.5844L37.7048 51.7847L36.4492 52.1847C36.4031 52.1972 36.3341 52.2159 36.242 52.2409C36.1708 52.2701 36.0892 52.2972 35.9971 52.3222L35.407 52.4972L34.9299 52.597L34.6851 52.6783L34.6537 52.6719C34.7039 52.6385 34.7877 52.601 34.9049 52.5593L35.2878 52.4405C35.3087 52.4448 35.3213 52.4364 35.3255 52.4155C35.4176 52.3905 35.5013 52.353 35.5767 52.3028C35.6688 52.2779 35.7608 52.2529 35.8529 52.2279C35.9659 52.2071 36.058 52.1821 36.1291 52.1529C36.2254 52.107 36.3091 52.0695 36.3803 52.0403L36.5938 51.9527L36.6315 51.9276L36.6001 51.9213L36.3302 51.9649C36.2548 52.015 36.1251 52.0651 35.9409 52.115L35.3885 52.265L35.0118 52.3523L34.9741 52.3774C34.9281 52.3899 34.882 52.4024 34.836 52.4149C34.79 52.4274 34.7418 52.4503 34.6916 52.4837L34.6602 52.4774C34.6226 52.4481 34.5808 52.4396 34.5347 52.4521C34.4845 52.4855 34.4384 52.498 34.3966 52.4896C34.3715 52.5063 34.338 52.5105 34.2962 52.502C34.2753 52.4978 34.2522 52.5041 34.2271 52.5208L34.1894 52.5458L33.9509 52.5957C33.9509 52.5957 33.93 52.5915 33.8882 52.5831C33.9091 52.5873 33.9216 52.579 33.9258 52.5581L34.133 52.5018L34.1707 52.4768L34.1143 52.4328C33.9888 52.4075 33.8758 52.4283 33.7753 52.4951C33.7502 52.5118 33.7062 52.5138 33.6435 52.5012C33.6393 52.5221 33.6288 52.52 33.6121 52.4949C33.6121 52.4949 33.5996 52.5032 33.5745 52.52L33.1915 52.6387L33.1098 52.7202C33.0889 52.716 33.0784 52.7139 33.0784 52.7139C33.0742 52.7348 33.0721 52.7452 33.0721 52.7452L33.0094 52.7326L32.8839 52.7073L33.0033 52.6008L33.2041 52.576L33.2732 52.5572C33.3318 52.482 33.4072 52.4319 33.4993 52.4069C33.5872 52.4028 33.6436 52.3924 33.6688 52.3757L34.1585 52.2132L34.1962 52.1881L34.1648 52.1818L34.077 52.1315C34.1188 52.1399 34.1837 52.1421 34.2715 52.138C34.3594 52.1339 34.4264 52.1257 34.4724 52.1132L34.7173 52.0319C34.8429 51.9484 34.9057 51.9066 34.9057 51.9066L35.0815 51.8441C35.1024 51.8483 35.1129 51.8504 35.1129 51.8504C35.1171 51.8295 35.1192 51.819 35.1192 51.819L35.0878 51.8127L34.9497 51.8502C34.8827 51.8585 34.7781 51.8918 34.6358 51.9502L34.077 52.1315L33.7631 52.2315L32.8214 52.5315L31.9927 52.7564L31.7478 52.8377C31.6515 52.8836 31.5595 52.9086 31.4716 52.9126C31.4046 52.9209 31.3481 52.9313 31.3021 52.9438L31.2394 52.9312ZM29.4407 51.0022C29.4407 51.0022 29.4428 50.9918 29.447 50.9709C29.447 50.9709 29.4575 50.973 29.4784 50.9772L29.491 50.9145L29.4786 50.814L29.3969 50.8955L29.4283 50.9018L29.4156 50.9646C29.4114 50.9855 29.4198 50.998 29.4407 51.0022ZM29.9171 51.3919L29.9298 51.3292L29.911 51.2602C29.9026 51.302 29.8879 51.3208 29.867 51.3166L29.8544 51.3793L29.8731 51.4484L29.9171 51.3919ZM31.3893 53.4836C31.3935 53.4627 31.3956 53.4523 31.3956 53.4523C31.4165 53.4565 31.427 53.4586 31.427 53.4586L31.496 53.4398L32.0862 53.2649C32.1364 53.2315 32.172 53.2169 32.1929 53.2211L32.2243 53.2274C32.2368 53.2734 32.22 53.3027 32.174 53.3152C32.1488 53.3319 32.1363 53.3402 32.1363 53.3402L31.5588 53.4525L31.4206 53.49L31.3893 53.4836ZM31.1273 52.1905L31.1337 52.1591L30.9955 52.1966C30.9746 52.1924 30.9621 52.2008 30.9579 52.2217L30.9892 52.228L31.1273 52.1905ZM31.7223 53.1263C31.7223 53.1263 31.7119 53.1242 31.691 53.12C31.691 53.12 31.6931 53.1096 31.6973 53.0887L31.6345 53.076L31.7036 53.0573C31.7539 53.0239 31.8459 52.9989 31.9798 52.9823C32.0007 52.9865 32.0091 52.9991 32.0049 53.02L31.9986 53.0514C31.8647 53.068 31.7726 53.0929 31.7223 53.1263ZM29.5603 50.7325L29.7426 50.4755L29.8622 50.2058L30.0194 49.911L30.0007 49.842L29.9253 49.8921C29.8876 49.9715 29.8351 50.0698 29.7681 50.1868C29.701 50.3039 29.6401 50.444 29.5855 50.6071L29.5352 50.6949L29.5226 50.7576L29.5603 50.7325ZM31.2718 52.1217C31.3136 52.1301 31.3366 52.1238 31.3408 52.1029L31.6547 52.0029L31.7301 51.9528C31.6883 51.9444 31.6548 51.9485 31.6297 51.9652C31.6088 51.961 31.5146 51.9964 31.3471 52.0715L31.2781 52.0903L31.2718 52.1217ZM31.3151 52.5547C31.4491 52.5382 31.5265 52.532 31.5474 52.5362C31.5516 52.5153 31.5746 52.509 31.6164 52.5175C31.6122 52.5384 31.6206 52.5509 31.6415 52.5551L31.9868 52.4615C32.0077 52.4657 32.0307 52.4594 32.0558 52.4427C32.1019 52.4302 32.1186 52.401 32.1061 52.3549L32.3573 52.2423C32.6084 52.184 32.7591 52.1382 32.8093 52.1048L32.8784 52.086L32.847 52.0797C32.8303 52.0546 32.8011 52.0378 32.7592 52.0294L32.5394 52.1484C32.4641 52.1985 32.4076 52.2089 32.3699 52.1795C32.3281 52.1711 32.2612 52.1794 32.1691 52.2044C32.1231 52.2169 32.1084 52.2357 32.1251 52.2608L32.056 52.2795C32.0393 52.2544 31.9849 52.2544 31.8929 52.2793C31.8175 52.3294 31.7693 52.3524 31.7484 52.3482C31.7066 52.3398 31.6585 52.3627 31.604 52.417C31.5455 52.3835 31.4911 52.3834 31.4408 52.4168C31.3906 52.4502 31.3529 52.4753 31.3278 52.492L31.2587 52.5107L31.3151 52.5547ZM32.3632 52.5372C32.4093 52.5247 32.4553 52.5123 32.5013 52.4998C32.5474 52.4873 32.5955 52.4643 32.6458 52.4309L32.7022 52.4749L32.6834 52.4059L32.6207 52.3932L32.4826 52.4307L32.0619 52.5745L31.9929 52.5933L32.0807 52.6436L32.3632 52.5372ZM32.4319 52.8448L32.4695 52.8198L32.7771 52.7511L32.8022 52.7888L32.7582 52.8453L32.4883 52.8888L32.4319 52.8448ZM31.7297 52.2791L32.571 51.9915L32.6024 51.9978C32.6066 51.9769 32.5982 51.9644 32.5773 51.9601L32.5083 51.9789C32.0646 52.1289 31.8072 52.2186 31.736 52.2478L31.667 52.2665L31.7297 52.2791ZM31.7682 51.6014L32.0131 51.5201L32.0571 51.4637L31.9943 51.4511L31.7368 51.5951L31.7682 51.6014ZM32.9157 52.3873L32.922 52.356L32.9032 52.2869L32.7338 52.3181L32.7211 52.3808L32.7525 52.3871L32.8466 52.4061C32.8382 52.4479 32.8591 52.4521 32.9094 52.4187L32.9157 52.3873ZM32.4897 51.7467L32.4961 51.7153L32.4647 51.709L32.2889 51.7715C32.2847 51.7924 32.293 51.805 32.3139 51.8092L32.4897 51.7467ZM32.396 51.4014C32.4463 51.368 32.4923 51.3555 32.5342 51.3639L32.5091 51.3262L32.3396 51.3574L32.3333 51.3887L32.396 51.4014ZM32.7091 51.954L32.9163 51.8978L33.2616 51.8041L33.2993 51.7791L33.2679 51.7728L33.1298 51.8102C32.9498 51.8393 32.7992 51.8851 32.6778 51.9477C32.6778 51.9477 32.6673 51.9456 32.6464 51.9414C32.6464 51.9414 32.6443 51.9519 32.6401 51.9728L32.6714 51.9791L32.7091 51.954ZM32.4906 51.094C32.5784 51.0899 32.66 51.0628 32.7354 51.0127L32.7668 51.019L32.7354 51.0127C32.5973 51.0502 32.5157 51.0773 32.4906 51.094ZM33.0165 52.0486L33.7825 51.8111C33.8034 51.8153 33.8138 51.8174 33.8138 51.8174C33.818 51.7965 33.8201 51.786 33.8201 51.786L33.8265 51.7546C33.8265 51.7546 33.816 51.7525 33.7951 51.7483C33.7951 51.7483 33.793 51.7588 33.7888 51.7797L33.4121 51.8671L33.0228 52.0172L32.9538 52.0359L33.0165 52.0486ZM33.0664 52.2871L33.6252 52.1058C33.6754 52.0724 33.7006 52.0557 33.7006 52.0557L33.8073 52.0119L34.0458 51.962C34.0961 51.9286 34.1212 51.9119 34.1212 51.9119L34.0271 51.893L33.7069 52.0243L33.7006 52.0557L33.6064 52.0368L33.3239 52.1431L33.0477 52.218L33.0037 52.2745L33.0664 52.2871ZM33.1557 51.1952L33.5073 51.0702L33.5826 51.0201L33.5513 51.0137L33.4508 51.0262L33.1306 51.1576L33.1243 51.1889L33.1557 51.1952ZM34.2408 51.6422L34.2471 51.6108C34.155 51.6358 34.0839 51.665 34.0336 51.6984L34.065 51.7047L34.2408 51.6422ZM34.4728 51.7868C34.4937 51.791 34.5042 51.7932 34.5042 51.7932C34.5084 51.7722 34.5105 51.7618 34.5105 51.7618C34.5105 51.7618 34.5 51.7597 34.4791 51.7555C34.4833 51.7346 34.4729 51.7324 34.4478 51.7491L34.2656 51.8431L34.2593 51.8744L34.4728 51.7868ZM34.6109 51.7494L34.9625 51.6243C34.9834 51.6285 34.996 51.6201 35.0002 51.5992L35.0065 51.5679C34.9898 51.5427 34.9585 51.5364 34.9124 51.5489C34.8915 51.5447 34.8685 51.551 34.8434 51.5677C34.8349 51.6095 34.8098 51.6262 34.768 51.6178C34.7304 51.5884 34.6969 51.5926 34.6676 51.6302C34.6382 51.6678 34.611 51.695 34.5859 51.7117L34.5796 51.743L34.6109 51.7494ZM35.9342 52.4727L36.0723 52.4353C36.0974 52.4186 36.11 52.4102 36.11 52.4102C36.1267 52.4353 36.1455 52.45 36.1664 52.4542L36.1287 52.4793L35.9279 52.5041L35.9342 52.4727ZM35.3644 51.4114C35.3771 51.3487 35.4105 51.3445 35.4649 51.399C35.4858 51.4032 35.4983 51.3949 35.5026 51.3739L35.5466 51.3175L35.5215 51.2798C35.4546 51.2881 35.3834 51.3173 35.308 51.3674C35.2578 51.4008 35.2284 51.4384 35.22 51.4803L35.2764 51.5243L35.3644 51.4114ZM35.9546 51.2365C36.0048 51.203 36.03 51.1863 36.03 51.1863L36.0927 51.199L36.1554 51.2116C36.1639 51.1698 36.1576 51.1468 36.1367 51.1426L36.074 51.1299L36.03 51.1863C35.9965 51.1361 35.9924 51.1026 36.0175 51.0859L36.0489 51.0922C36.0489 51.0922 36.0384 51.0901 36.0175 51.0859C36.0217 51.065 36.0217 51.065 36.0175 51.0859C35.9757 51.0775 35.9527 51.0837 35.9485 51.1047L35.9045 51.1611C35.9003 51.182 35.9065 51.205 35.9232 51.2301C35.9441 51.2343 35.9546 51.2365 35.9546 51.2365ZM35.416 50.3446L35.5227 50.3008L35.4914 50.2945C35.4495 50.2861 35.4265 50.2923 35.4223 50.3132L35.3156 50.357L35.416 50.3446ZM35.912 50.1507L35.9183 50.1193C35.9183 50.1193 35.9079 50.1172 35.887 50.113C35.887 50.113 35.8849 50.1235 35.8807 50.1444C35.8597 50.1402 35.7656 50.1756 35.5981 50.2507L35.5918 50.2821L35.912 50.1507ZM34.0256 48.1715C34.0298 48.1505 34.0423 48.1422 34.0632 48.1464C34.1219 48.0712 34.1701 47.9938 34.2079 47.9144C34.2665 47.8391 34.3378 47.7556 34.4216 47.6636L34.673 47.3878L34.7043 47.3941L34.6666 47.4192L34.3586 47.8142C34.2413 47.9646 34.1428 48.0754 34.0632 48.1464C34.0632 48.1464 34.0611 48.1569 34.0569 48.1778C34.0569 48.1778 34.0465 48.1757 34.0256 48.1715ZM36.2748 51.1051C36.2957 51.1093 36.3187 51.103 36.3439 51.0863C36.3899 51.0738 36.4171 51.0467 36.4256 51.0049L36.4569 51.0112C36.503 50.9987 36.5678 51.0008 36.6515 51.0177C36.6724 51.0219 36.6849 51.0135 36.6892 50.9926C36.6892 50.9926 36.7771 50.9342 36.953 50.8173C36.9572 50.7963 36.9593 50.7859 36.9593 50.7859C36.9802 50.7901 36.9906 50.7922 36.9906 50.7922L36.9843 50.8236L37.0471 50.8362L37.2669 50.7172C37.3171 50.6838 37.3485 50.6901 37.361 50.7362L37.3924 50.7425L37.4991 50.6987C37.52 50.7029 37.5305 50.705 37.5305 50.705C37.5347 50.6841 37.5368 50.6737 37.5368 50.6737C37.4867 50.5983 37.5034 50.569 37.5871 50.5859C37.5913 50.5649 37.6039 50.5566 37.6248 50.5608L37.5934 50.5545C37.5516 50.5461 37.4846 50.5543 37.3926 50.5793L37.3235 50.5981L37.242 50.5164C37.1666 50.5665 37.129 50.5915 37.129 50.5915C37.1038 50.6083 37.0557 50.6312 36.9845 50.6604L36.9532 50.6541L36.6266 50.8168C36.6057 50.8126 36.591 50.8314 36.5826 50.8733L36.5763 50.9046L36.5449 50.8983C36.5073 50.869 36.4634 50.871 36.4131 50.9044L36.3691 50.9608C36.3858 50.986 36.3816 51.0069 36.3565 51.0236C36.3314 51.0403 36.2979 51.0444 36.2561 51.036C36.2645 50.9942 36.2561 50.9816 36.231 50.9983C36.1892 50.9899 36.1641 51.0066 36.1556 51.0484C36.21 51.1029 36.2497 51.1218 36.2748 51.1051ZM36.0878 50.0882C36.1087 50.0924 36.1213 50.084 36.1255 50.0631L36.3013 50.0006L36.4771 49.938L36.5148 49.913L36.4207 49.894C36.2784 49.9524 36.1695 50.0067 36.0941 50.0568L36.0878 50.0882ZM36.6902 50.1768C36.6902 50.1768 36.6881 50.1872 36.6839 50.2082C36.7048 50.2124 36.7173 50.204 36.7216 50.1831L36.8597 50.1456L36.9287 50.1269L36.866 50.1143L36.6902 50.1768ZM37.2601 51.0749L37.9006 50.8122L37.932 50.8185L37.8755 50.7745C37.8713 50.7954 37.8483 50.8017 37.8065 50.7932L37.5867 50.9122L37.1974 51.0623L37.1597 51.0874L37.1911 51.0937L37.2601 51.0749ZM36.9727 50.0705C37.0146 50.0789 37.048 50.0747 37.0732 50.058C37.0941 50.0623 37.1297 50.0477 37.1799 50.0142L37.1172 50.0016L37.0481 50.0204C36.9979 50.0538 36.9727 50.0705 36.9727 50.0705ZM37.5433 50.4791L37.5496 50.4477L37.4869 50.4351L37.3801 50.4789C37.422 50.4873 37.4429 50.4915 37.4429 50.4915L37.5433 50.4791ZM31.9008 50.9426L32.6291 50.7302C32.7714 50.6718 32.9807 50.6051 33.2569 50.5301L34.1045 50.2112C34.2175 50.1904 34.3912 50.1383 34.6256 50.0549C34.6968 50.0257 34.7784 49.9986 34.8705 49.9737C34.9668 49.9278 35.0735 49.884 35.1907 49.8423L36.4213 49.4045C36.6055 49.3546 36.865 49.2545 37.1999 49.1043L38.0351 48.6849C38.2067 48.5889 38.46 48.4658 38.7949 48.3156C39.1885 48.0902 39.4649 47.9064 39.624 47.7644C39.7371 47.6348 39.8084 47.5512 39.8377 47.5136L39.8943 47.3944L40.1082 46.9805L40.1272 46.8864C40.1482 46.7818 40.1254 46.6793 40.0585 46.5788C40.0376 46.5746 40.0272 46.5725 40.0272 46.5725C40.0314 46.5516 40.0335 46.5411 40.0335 46.5411L40.0649 46.5474C40.0649 46.5474 40.0983 46.5977 40.1651 46.6982L40.2906 46.7234C40.2906 46.7234 40.2927 46.713 40.2969 46.6921C40.322 46.6754 40.3262 46.6545 40.3095 46.6293C40.3221 46.5666 40.2992 46.5184 40.2407 46.4849C40.2073 46.4347 40.1843 46.3865 40.1718 46.3405C40.1551 46.3154 40.128 46.2881 40.0903 46.2588C40.0527 46.2295 40.0256 46.2022 40.0089 46.1771C40.0131 46.1562 40.0026 46.1541 39.9775 46.1708C39.9524 46.1875 39.9189 46.1916 39.8771 46.1832C39.8394 46.1539 39.8102 46.1371 39.7893 46.1329C39.7683 46.1287 39.7391 46.1119 39.7015 46.0826C39.6638 46.0532 39.6241 46.0344 39.5823 46.0259C39.5238 45.9924 39.4318 45.963 39.3063 45.9377L38.4028 45.7232L38.0891 45.6601C37.9427 45.6306 37.8256 45.6179 37.7377 45.6219C37.6917 45.6344 37.6373 45.6344 37.5746 45.6217C37.516 45.5882 37.4638 45.5777 37.4177 45.5902C37.3341 45.5733 37.2253 45.5732 37.0914 45.5897C37.0705 45.5855 37.0579 45.5939 37.0537 45.6148L37.0851 45.6211C37.2524 45.6548 37.3758 45.6905 37.4552 45.7283L37.4866 45.7346L37.4552 45.7283L37.223 45.7468L37.1602 45.7342C37.1393 45.73 37.1268 45.7383 37.1226 45.7592C37.1226 45.7592 37.1204 45.7697 37.1162 45.7906C37.1162 45.7906 37.1267 45.7927 37.1476 45.7969L37.3045 45.8285L37.5241 45.8727L37.5491 45.9104L37.5177 45.9041L37.455 45.8914L36.8777 45.8405L36.815 45.8279C36.8107 45.8488 36.8086 45.8592 36.8086 45.8592C36.8296 45.8635 36.84 45.8656 36.84 45.8656L36.8337 45.8969C36.8295 45.9178 36.8378 45.9304 36.8587 45.9346L37.5803 46.0799L37.574 46.1112L37.7371 46.1115L37.7936 46.1555L37.7245 46.1742L37.0971 46.0479C36.8879 46.0058 36.662 45.9929 36.4194 46.0094C36.3691 46.0428 36.3231 46.0553 36.2812 46.0468L35.9235 46.0401C35.6893 46.0147 35.526 46.1233 35.4336 46.3658L35.3016 46.5351C35.3016 46.5351 35.2765 46.5518 35.2262 46.5852C35.2262 46.5852 35.222 46.6061 35.2136 46.648C35.2261 46.694 35.2135 46.7023 35.1759 46.673L35.1445 46.6667C35.1361 46.7085 35.1026 46.7671 35.0439 46.8423L34.8363 47.2248L34.7923 47.2813L34.7673 47.2436L34.8113 47.1872L34.8176 47.1558C34.826 47.114 34.8093 47.0888 34.7675 47.0804C34.7633 47.1013 34.7486 47.1201 34.7235 47.1368C34.7026 47.1326 34.7005 47.1431 34.7172 47.1682C34.7003 47.2519 34.6793 47.302 34.6542 47.3188C34.6291 47.3355 34.604 47.3522 34.5788 47.3689C34.5537 47.3856 34.5369 47.4148 34.5285 47.4567C34.3023 47.7158 34.143 47.9122 34.0508 48.046C33.967 48.1379 33.9314 48.2069 33.9439 48.2529C33.9439 48.2529 33.9334 48.2508 33.9125 48.2466C33.9125 48.2466 33.9104 48.2571 33.9062 48.278C33.7428 48.4409 33.6611 48.5224 33.6611 48.5224C33.6024 48.5977 33.4285 48.8129 33.1394 49.1682C32.7958 49.5777 32.5779 49.8494 32.4857 49.9832C32.3642 50.1546 32.2447 50.3155 32.1274 50.466C32.0309 50.6206 31.9366 50.7649 31.8444 50.8986L31.8318 50.9614L31.9008 50.9426ZM37.5064 49.8515L37.4751 49.8452L37.3683 49.889C37.3641 49.9099 37.362 49.9203 37.362 49.9203C37.3829 49.9246 37.3934 49.9267 37.3934 49.9267L37.5064 49.8515ZM37.8204 49.7515L38.2473 49.5763L38.2536 49.5449L38.2223 49.5386C38.1972 49.5553 38.1637 49.5595 38.1218 49.551C38.1009 49.5468 38.0779 49.5531 38.0528 49.5698C38.0444 49.6116 38.0318 49.62 38.0151 49.5948C38.0193 49.5739 38.011 49.5614 37.9901 49.5571L37.9524 49.5822L37.9711 49.6513L37.902 49.67L37.7953 49.7138L37.789 49.7452L37.8204 49.7515ZM37.8383 50.4732C37.9052 50.4649 37.9617 50.4545 38.0078 50.442C38.0747 50.4338 38.1312 50.4234 38.1772 50.4109C38.2024 50.3942 38.2254 50.3879 38.2463 50.3921C38.2672 50.3964 38.2798 50.388 38.284 50.3671C38.2673 50.342 38.2966 50.3043 38.372 50.2542C38.4222 50.2208 38.439 50.1916 38.4223 50.1664L38.4286 50.1351C38.4328 50.1142 38.4349 50.1037 38.4349 50.1037C38.4558 50.1079 38.4663 50.11 38.4663 50.11C38.483 50.1351 38.4914 50.1477 38.4914 50.1477C38.5165 50.131 38.5395 50.1248 38.5604 50.129C38.5646 50.1081 38.5876 50.1018 38.6295 50.1102C38.6713 50.1186 38.686 50.0998 38.6735 50.0538L38.7362 50.0664L38.7676 50.0727L38.7739 50.0414L38.7802 50.01L38.9057 50.0353C38.9057 50.0353 38.9204 50.0165 38.9497 49.9788C38.9999 49.9454 39.0418 49.9539 39.0752 50.0041L39.0815 49.9727C39.182 49.9059 39.2469 49.8537 39.2762 49.8161L39.2826 49.7847C39.3035 49.7889 39.3139 49.791 39.3139 49.791C39.3391 49.7743 39.3516 49.766 39.3516 49.766L39.3266 49.7283L39.2952 49.722C39.2952 49.722 39.2847 49.7199 39.2638 49.7157C39.2638 49.7157 39.2659 49.7052 39.2701 49.6843C39.2743 49.6634 39.2869 49.655 39.3078 49.6592C39.3162 49.6174 39.3309 49.5986 39.3518 49.6028C39.3351 49.5777 39.2954 49.5588 39.2327 49.5462L39.22 49.6089L39.1697 49.6967L39.1133 49.6527L39.0819 49.6464L39.0756 49.6778L39.1007 49.7155C39.1174 49.7406 39.1131 49.7615 39.088 49.7782C39.042 49.7907 38.975 49.799 38.8872 49.803C38.7993 49.8071 38.7365 49.8489 38.6987 49.9283L38.6674 49.922C38.6171 49.9554 38.5815 49.97 38.5606 49.9658C38.4601 50.0326 38.3869 50.0723 38.3408 50.0848C38.3157 50.1015 38.2968 50.1412 38.2842 50.2039L38.209 50.0909L38.1463 50.0782L38.1086 50.1033L38.165 50.1473L38.1964 50.1536C38.1922 50.1745 38.1796 50.1829 38.1587 50.1787C38.1587 50.1787 38.121 50.2037 38.0456 50.2538L37.8886 50.3854L37.606 50.4917L37.5997 50.5231L37.6311 50.5294L37.8383 50.4732ZM38.3227 49.5262C38.373 49.4928 38.4085 49.4782 38.4294 49.4824L38.5048 49.4323L38.4107 49.4133L38.304 49.4571L38.2663 49.4822L38.3227 49.5262ZM38.5865 49.3508C38.6032 49.3759 38.6137 49.378 38.6179 49.3571C38.643 49.3404 38.666 49.3342 38.6869 49.3384C38.7288 49.3468 38.7539 49.3301 38.7623 49.2883L38.7686 49.2569L38.6996 49.2756L38.5865 49.3508ZM39.7146 50.5572L40.0098 50.3881L40.0538 50.3317C40.0538 50.3317 40.0433 50.3296 40.0224 50.3254C40.0224 50.3254 40.0203 50.3358 40.0161 50.3567L39.6895 50.5195L39.6832 50.5509L39.7146 50.5572ZM36.7082 45.8717L36.7145 45.8403L36.6581 45.7963L36.4949 45.7961L36.4886 45.8275L36.52 45.8338L36.6392 45.8904L36.7082 45.8717ZM39.0825 49.1569L39.3023 49.0379L39.3087 49.0066L39.2773 49.0002C39.2103 49.0085 39.1475 49.0503 39.0889 49.1255L39.0512 49.1506L39.0825 49.1569ZM40.1228 50.3129C40.1689 50.3005 40.2421 50.2608 40.3426 50.194C40.3217 50.1898 40.3113 50.1877 40.3113 50.1877L40.0978 50.2753L40.0915 50.3066L40.1228 50.3129ZM37.0912 45.7529L36.972 45.6963L36.8716 45.7087C36.8883 45.7338 36.9176 45.7506 36.9594 45.759L37.0912 45.7529ZM39.4333 49.6845C39.4375 49.6636 39.4501 49.6552 39.471 49.6594C39.4961 49.6427 39.5066 49.6448 39.5024 49.6658C39.5233 49.67 39.5463 49.6637 39.5714 49.647L39.6405 49.6283L39.6217 49.5592C39.6302 49.5174 39.6239 49.4944 39.603 49.4902C39.6239 49.4944 39.6344 49.4965 39.6344 49.4965C39.7263 49.5803 39.8163 49.5657 39.9043 49.4529L39.9733 49.4342L40.0801 49.3904C40.1973 49.3487 40.2978 49.2819 40.3816 49.1899C40.4318 49.1565 40.4716 49.121 40.5009 49.0834C40.5512 49.05 40.6014 49.0166 40.6517 48.9832C40.6726 48.9874 40.6873 48.9686 40.6957 48.9267L40.6393 48.8827C40.6141 48.8994 40.5911 48.9057 40.5702 48.9015C40.5744 48.8806 40.5891 48.8618 40.6142 48.8451C40.6351 48.8493 40.6351 48.8493 40.6142 48.8451C40.6184 48.8241 40.6205 48.8137 40.6205 48.8137L40.5892 48.8074L40.4258 48.9703L40.4195 49.0017C40.4362 49.0268 40.432 49.0477 40.4068 49.0644C40.4068 49.0644 40.3964 49.0623 40.3755 49.0581C40.3127 49.0455 40.2416 49.0747 40.162 49.1457C40.1075 49.2 40.0594 49.223 40.0175 49.2146L40.0112 49.2459C39.9526 49.3212 39.8835 49.3399 39.8041 49.3021L39.7413 49.2895C39.712 49.3271 39.7015 49.325 39.7099 49.2832L39.6535 49.2392C39.6535 49.2392 39.6284 49.2559 39.5781 49.2893C39.6158 49.3186 39.6304 49.3542 39.6219 49.3961C39.6344 49.4421 39.6386 49.4756 39.6344 49.4965C39.5591 49.4378 39.509 49.4168 39.4838 49.4335C39.4629 49.4293 39.4504 49.4377 39.4461 49.4586C39.5047 49.4921 39.4963 49.534 39.4209 49.5841C39.3958 49.6008 39.3811 49.6196 39.3769 49.6405C39.3727 49.6614 39.3685 49.6823 39.3642 49.7032L39.4144 49.7786L39.4333 49.6845ZM40.4557 50.1188C40.4557 50.1188 40.5813 50.0353 40.8326 49.8683C40.8535 49.8725 40.8639 49.8746 40.8639 49.8746C40.8681 49.8537 40.8702 49.8432 40.8702 49.8432L40.8075 49.8306C40.707 49.8974 40.6568 49.9308 40.6568 49.9308L40.3993 50.0748L40.3866 50.1376L40.418 50.1439L40.4557 50.1188ZM37.4746 45.3078C37.4537 45.3036 37.4265 45.2764 37.3931 45.2261L37.3554 45.2512L37.4306 45.3643L37.4746 45.3078ZM40.0247 48.5305L40.1001 48.4804C40.0791 48.4762 40.0687 48.4741 40.0687 48.4741L39.9996 48.4928L39.9556 48.5493L40.0247 48.5305ZM37.9266 45.1703L37.8702 45.1263C37.8535 45.1012 37.8326 45.097 37.8074 45.1137C37.7865 45.1095 37.7677 45.0948 37.751 45.0697C37.751 45.0697 37.7405 45.0676 37.7196 45.0634C37.7196 45.0634 37.7175 45.0738 37.7133 45.0948C37.7133 45.0948 37.7112 45.1052 37.707 45.1261C37.707 45.1261 37.7175 45.1282 37.7384 45.1324L37.8011 45.1451L37.8639 45.1577L37.9266 45.1703ZM38.8673 45.6861L38.8486 45.6171L38.4157 45.4973L38.3529 45.4847C38.3278 45.5014 38.3048 45.5076 38.2839 45.5034C38.2881 45.4825 38.2797 45.4699 38.2588 45.4657C38.1919 45.474 38.1501 45.4656 38.1333 45.4405C38.1376 45.4195 38.1271 45.4174 38.102 45.4341C38.0811 45.4299 38.0602 45.4257 38.0392 45.4215C37.9807 45.388 37.9389 45.3795 37.9138 45.3962C37.9053 45.4381 37.8802 45.4548 37.8384 45.4464L37.8447 45.415L37.826 45.3459C37.826 45.3459 37.8155 45.3438 37.7946 45.3396C37.7946 45.3396 37.7925 45.3501 37.7883 45.371L37.7756 45.4337L37.8384 45.4464C37.8969 45.4799 37.9889 45.5093 38.1144 45.5346L38.8359 45.6798L38.8673 45.6861ZM36.9309 43.4684L37 43.4496C37.0209 43.4538 37.0334 43.4455 37.0377 43.4246L37.0063 43.4182L36.9059 43.4307C36.8849 43.4265 36.8724 43.4348 36.8682 43.4557L36.9309 43.4684ZM37.4516 43.6385C37.3888 43.6258 37.3449 43.6279 37.3198 43.6446C37.3198 43.6446 37.3093 43.6425 37.2884 43.6383C37.2884 43.6383 37.2863 43.6487 37.2821 43.6696L37.3072 43.7073L37.4516 43.6385ZM40.2478 45.8009C40.1726 45.7422 40.114 45.7086 40.0722 45.7002C40.0346 45.6709 39.974 45.6478 39.8903 45.631L39.8276 45.6183L39.7962 45.612C39.721 45.5533 39.6708 45.5324 39.6457 45.5491C39.6205 45.5658 39.608 45.5741 39.608 45.5741C39.6122 45.5532 39.6143 45.5428 39.6143 45.5428C39.6394 45.526 39.6206 45.5114 39.5579 45.4987L39.4638 45.4798L39.3069 45.4482C39.2735 45.398 39.2317 45.3896 39.1814 45.423L39.1187 45.4103C39.102 45.3852 39.0727 45.3684 39.0309 45.36C38.9891 45.3516 38.9598 45.3348 38.9431 45.3097L38.8803 45.2971C38.9013 45.3013 38.9096 45.3138 38.9054 45.3348L38.7172 45.2969C38.6335 45.28 38.5624 45.2548 38.5039 45.2213C38.4621 45.2129 38.3972 45.2107 38.3094 45.2148C38.2466 45.2021 38.1881 45.1686 38.1338 45.1141L38.1024 45.1078L37.9957 45.1516L37.9643 45.1453L37.983 45.2143L38.2403 45.2335L38.234 45.2649C38.2591 45.2482 38.2926 45.244 38.3344 45.2524L38.4536 45.3091L38.7359 45.3659L39.1374 45.4794C39.2587 45.5256 39.4009 45.5759 39.564 45.6305C39.748 45.6894 39.8923 45.7293 39.9968 45.7503C40.0345 45.7797 40.0951 45.8028 40.1788 45.8196L40.2415 45.8322L40.2478 45.8009ZM37.1695 43.4184C37.4248 43.3393 37.5754 43.2935 37.6215 43.281C37.6424 43.2852 37.655 43.2768 37.6592 43.2559L37.9291 43.2123L37.9668 43.1873C37.9249 43.1788 37.904 43.1746 37.904 43.1746C37.8371 43.1829 37.7806 43.1933 37.7345 43.2058C37.7094 43.2225 37.6843 43.2392 37.6592 43.2559L37.5964 43.2433C37.5504 43.2558 37.4813 43.2745 37.3893 43.2995C37.3181 43.3287 37.2365 43.3558 37.1444 43.3808L37.1695 43.4184ZM40.2661 46.1963L40.2724 46.1649L40.191 46.0832C40.1282 46.0706 40.0383 46.0307 39.9213 45.9636C39.8836 45.9343 39.8335 45.9133 39.7707 45.9007C39.708 45.888 39.6578 45.8671 39.6202 45.8377L39.5888 45.8314C39.5637 45.8481 39.5323 45.8418 39.4947 45.8125L39.1623 45.6802L39.0932 45.699L39.0618 45.6927L38.9677 45.6737C38.9468 45.6695 38.9342 45.6779 38.93 45.6988C38.9467 45.7239 38.9865 45.7428 39.0492 45.7554L39.2374 45.7933C39.2793 45.8017 39.3587 45.8395 39.4758 45.9066C39.5385 45.9192 39.641 45.9507 39.7832 46.0011C39.9463 46.0557 40.0759 46.1144 40.172 46.1773L40.2348 46.1899L40.2661 46.1963ZM37.6211 43.6073L37.8282 43.5511C37.8743 43.5386 37.9203 43.5261 37.9664 43.5136C38.0124 43.5011 38.0605 43.4782 38.1108 43.4447L38.2426 43.4386L38.3116 43.4199L38.2866 43.3822L38.2175 43.401L37.5333 43.557L37.4893 43.6134L37.552 43.626L37.6211 43.6073ZM41.3368 48.1745L41.3934 48.0553L41.4877 47.9111L41.494 47.8797C41.494 47.8797 41.4836 47.8776 41.4627 47.8734C41.4627 47.8734 41.4606 47.8838 41.4563 47.9048C41.3894 47.913 41.3684 47.9632 41.3934 48.0553C41.3432 48.0887 41.3138 48.1263 41.3054 48.1682L41.3368 48.1745ZM38.3171 44.0412C38.338 44.0454 38.4322 44.01 38.5997 43.9349L38.6123 43.8721L38.5809 43.8658L38.5496 43.8595L38.6186 43.8408L38.675 43.8848L38.7064 43.8911C38.7315 43.8744 38.7483 43.8451 38.7567 43.8033L38.7254 43.797C38.6375 43.801 38.535 43.8239 38.4178 43.8656C38.3257 43.8906 38.2462 43.9072 38.1792 43.9155L38.1603 44.0096L38.3171 44.0412ZM41.6387 47.6477C41.6471 47.6059 41.6639 47.5766 41.689 47.5599L41.6953 47.5285L41.6262 47.5473L41.5822 47.6037C41.5738 47.6455 41.578 47.679 41.5947 47.7041L41.6387 47.6477ZM38.6369 44.2362C38.6411 44.2152 38.6537 44.2069 38.6746 44.2111L38.6809 44.1797L38.7123 44.186C38.7541 44.1945 38.7981 44.1924 38.8441 44.1799C38.8944 44.1465 38.9362 44.155 38.9696 44.2052C38.9654 44.2261 38.9758 44.2282 39.001 44.2115C39.0428 44.2199 39.1097 44.2117 39.2018 44.1867L39.2458 44.1302C39.25 44.1093 39.2312 44.0947 39.1894 44.0862L39.1267 44.0736L39.202 44.0235L39.2334 44.0298L39.3088 43.9797C39.2669 43.9713 39.246 43.9671 39.246 43.9671L39.1142 43.9732C39.064 44.0066 39.0472 44.0359 39.0639 44.061C39.0639 44.061 39.0618 44.0714 39.0576 44.0924C39.0576 44.0924 39.0471 44.0902 39.0262 44.086L38.6622 44.1107L38.5995 44.098C38.5952 44.119 38.5931 44.1294 38.5931 44.1294C38.6141 44.1336 38.6245 44.1357 38.6245 44.1357L38.6182 44.1671L38.6369 44.2362ZM40.4421 45.9706C40.4631 45.9748 40.4756 45.9664 40.4798 45.9455L40.4234 45.9015C40.4067 45.8764 40.3858 45.8722 40.3607 45.8889C40.3397 45.8847 40.3188 45.8804 40.2979 45.8762L40.2916 45.9076L40.4421 45.9706ZM38.243 43.1123L38.2807 43.0872C38.3016 43.0915 38.3099 43.104 38.3057 43.1249L38.4502 43.0561L38.4628 42.9933L38.4314 42.987L38.3247 43.0308C38.2117 43.0516 38.1301 43.0787 38.0798 43.1121L38.0735 43.1435C38.0484 43.1602 38.0358 43.1685 38.0358 43.1685C38.0567 43.1727 38.0672 43.1748 38.0672 43.1748L38.243 43.1123ZM38.9818 44.4688C39.0027 44.473 39.0362 44.4689 39.0822 44.4564C39.1492 44.4481 39.2078 44.4272 39.258 44.3938L39.4025 44.325C39.4694 44.3167 39.5531 44.2792 39.6536 44.2123L39.6913 44.1873L39.66 44.181L39.5532 44.2248C39.5323 44.2206 39.4758 44.2309 39.3837 44.2559C39.3628 44.2517 39.3293 44.2559 39.2833 44.2684C39.2624 44.2641 39.2477 44.283 39.2393 44.3248L39.2016 44.3498C39.1807 44.3456 39.1451 44.3602 39.0949 44.3936C39.0446 44.427 38.9902 44.427 38.9317 44.3934C38.9359 44.3725 38.9129 44.3788 38.8626 44.4122C38.8417 44.408 38.8271 44.4268 38.8186 44.4686L38.8751 44.5126L38.9818 44.4688ZM41.6892 47.3967L41.7332 47.3403C41.7416 47.2985 41.75 47.2566 41.7585 47.2148C41.792 47.1563 41.8004 47.1145 41.7837 47.0893C41.7503 47.0391 41.7357 47.0035 41.7399 46.9826C41.7608 46.9868 41.7608 46.9868 41.7399 46.9826C41.7441 46.9617 41.7462 46.9512 41.7462 46.9512C41.7462 46.9512 41.7358 46.9491 41.7149 46.9449C41.7149 46.9449 41.7128 46.9554 41.7086 46.9763C41.7043 46.9972 41.6897 47.016 41.6646 47.0327C41.6603 47.0536 41.6666 47.0766 41.6833 47.1018C41.7376 47.1562 41.7333 47.2315 41.6705 47.3277C41.6705 47.3277 41.6684 47.3381 41.6641 47.359C41.6641 47.359 41.6746 47.3611 41.6955 47.3654L41.6766 47.4595L41.6892 47.3967ZM41.3763 46.6809L41.389 46.6182C41.389 46.6182 41.3911 46.6077 41.3953 46.5868C41.3995 46.5659 41.3911 46.5533 41.3702 46.5491L41.2698 46.5615C41.2907 46.5657 41.2969 46.5888 41.2885 46.6306C41.3094 46.6348 41.3178 46.6474 41.3136 46.6683L41.3323 46.7373L41.3763 46.6809ZM39.3776 44.1241C39.4781 44.0573 39.5284 44.0239 39.5284 44.0239L39.497 44.0176L39.3589 44.0551L39.3776 44.1241ZM41.2824 46.4988C41.295 46.436 41.293 46.3921 41.2763 46.367L41.2826 46.3356C41.2868 46.3147 41.2785 46.3021 41.2576 46.2979L41.2262 46.2916L41.2011 46.2539C41.1802 46.2497 41.1698 46.2476 41.1698 46.2476C41.174 46.2267 41.1865 46.2183 41.2075 46.2226C41.2368 46.1849 41.2327 46.1515 41.195 46.1221C41.1741 46.1179 41.1532 46.1137 41.1323 46.1095C41.1365 46.0886 41.126 46.0865 41.1009 46.1032C41.1009 46.1032 41.0863 46.122 41.0569 46.1596C41.0527 46.1805 41.059 46.2035 41.0757 46.2287C41.1133 46.258 41.1655 46.3229 41.2323 46.4234C41.2741 46.4318 41.2908 46.457 41.2824 46.4988ZM38.4874 43.3574C38.5084 43.3616 38.5293 43.3658 38.5502 43.37C38.5962 43.3575 38.6444 43.3346 38.6946 43.3011L38.9708 43.2262L39.2597 43.0885L39.3351 43.0384C39.2932 43.03 39.2702 43.0362 39.266 43.0571L38.9521 43.1571C38.9061 43.1696 38.7554 43.2155 38.5001 43.2946L38.4624 43.3197L38.4561 43.3511L38.4874 43.3574ZM41.0885 46.0028L40.982 45.8834L40.9443 45.9084L41.0258 45.9901C41.0258 45.9901 41.0237 46.0006 41.0194 46.0215C41.0194 46.0215 41.0299 46.0236 41.0508 46.0278L41.0885 46.0028ZM41.4448 47.1517C41.4699 47.135 41.5055 47.1204 41.5515 47.1079C41.5975 47.0954 41.6164 47.0557 41.6081 46.9887L41.6458 46.9636L41.6961 46.8758C41.7255 46.8382 41.7527 46.8111 41.7778 46.7944C41.8239 46.7819 41.8552 46.7882 41.8719 46.8133C41.8886 46.8384 41.9032 46.874 41.9157 46.9201C41.9324 46.9452 41.9596 46.9724 41.9972 47.0017C42.0139 47.0269 42.0181 47.0603 42.0096 47.1022C42.0054 47.1231 42.0117 47.1461 42.0284 47.1712L42.0534 47.2089C42.0576 47.188 42.0597 47.1775 42.0597 47.1775C42.0807 47.1818 42.0911 47.1839 42.0911 47.1839C42.1204 47.1462 42.1289 47.1044 42.1164 47.0584C42.1081 46.9914 42.1082 46.937 42.1166 46.8952C42.1208 46.8743 42.1145 46.8513 42.0978 46.8262C42.0811 46.801 42.0602 46.7968 42.0351 46.8135L42.0037 46.8072L41.9412 46.6314C41.8661 46.464 41.7993 46.3635 41.7408 46.3299C41.6989 46.3215 41.6508 46.3444 41.5963 46.3988C41.5753 46.5033 41.5501 46.5744 41.5207 46.612C41.437 46.704 41.4138 46.819 41.4513 46.9571L41.426 47.0826L41.4134 47.1453L41.4448 47.1517ZM39.4782 43.9485L39.7545 43.8736L39.7985 43.8172L39.8048 43.7858L39.7734 43.7795L39.6103 43.7793C39.5893 43.7751 39.5663 43.7813 39.5412 43.798C39.5203 43.7938 39.5161 43.8147 39.5286 43.8607L39.4218 43.9045L39.3841 43.9296L39.4406 43.9736L39.4782 43.9485ZM38.5946 42.9872C38.6155 42.9914 38.6511 42.9768 38.7013 42.9434C38.7098 42.9016 38.7223 42.8933 38.739 42.9184L38.8018 42.931L38.8458 42.8746C38.8876 42.883 38.9462 42.8622 39.0216 42.8121L39.0906 42.7933C39.1325 42.8017 39.1659 42.7976 39.1911 42.7809C39.2371 42.7684 39.2643 42.7412 39.2727 42.6994C39.2309 42.691 39.1974 42.6951 39.1723 42.7118L39.1033 42.7306C39.0238 42.6928 38.9548 42.7116 38.8961 42.7868C38.8458 42.8202 38.8207 42.8369 38.8207 42.8369C38.6826 42.8744 38.601 42.9015 38.5759 42.9182C38.5549 42.914 38.5424 42.9223 38.5382 42.9432L38.5946 42.9872ZM39.9804 43.8864L40.1248 43.8176L40.445 43.6862L40.5581 43.611L40.6272 43.5923L40.5644 43.5797C40.3718 43.6715 40.2546 43.7131 40.2128 43.7047L40.1814 43.6984C40.1814 43.6984 40.0935 43.7569 39.9176 43.8738C39.9176 43.8738 39.9072 43.8717 39.8863 43.8675C39.8863 43.8675 39.8842 43.8779 39.88 43.8988L39.9113 43.9052L39.9804 43.8864ZM39.4041 43.0196C39.5716 42.9445 39.7348 42.8904 39.8938 42.8571L39.9378 42.8007L39.8751 42.788L39.7684 42.8318L39.3791 42.982L39.3728 43.0133L39.4041 43.0196ZM40.1564 43.6607C40.1857 43.6231 40.2234 43.5981 40.2695 43.5856C40.3364 43.5773 40.3803 43.5752 40.4012 43.5795C40.4222 43.5837 40.4577 43.5691 40.508 43.5357C40.4662 43.5272 40.4453 43.523 40.4453 43.523L40.1063 43.5854L40.0937 43.6481L40.1564 43.6607ZM38.483 41.9202C38.5248 41.9286 38.5478 41.9224 38.552 41.9015C38.552 41.9015 38.7279 41.7846 39.0797 41.5507L39.1677 41.4379L39.1239 41.3311C39.0611 41.3185 39.0172 41.3205 38.9921 41.3372C38.8916 41.404 38.8245 41.4667 38.791 41.5252L38.527 41.8638L38.483 41.9202ZM39.6372 42.3484C39.6874 42.315 39.723 42.3004 39.7439 42.3046L39.7502 42.2733L39.7189 42.267C39.7189 42.267 39.6937 42.2837 39.6435 42.3171C39.5932 42.3505 39.5681 42.3672 39.5681 42.3672L39.6372 42.3484ZM40.8783 43.4796C40.8825 43.4587 40.8742 43.4462 40.8533 43.442C40.8324 43.4377 40.7989 43.4419 40.7528 43.4544C40.7277 43.4711 40.711 43.5004 40.7025 43.5422L40.6962 43.5735L40.8783 43.4796ZM40.2267 42.663C40.2769 42.6296 40.3355 42.6087 40.4025 42.6004C40.4737 42.5712 40.5469 42.5316 40.6223 42.4815L40.6286 42.4501C40.6286 42.4501 40.6182 42.448 40.5972 42.4438C40.5972 42.4438 40.5951 42.4543 40.5909 42.4752C40.4988 42.5001 40.4277 42.5293 40.3774 42.5628C40.3105 42.571 40.2602 42.6044 40.2267 42.663L39.9818 42.7442L39.9755 42.7756L40.0069 42.7819L40.2267 42.663ZM39.6557 42.5807L39.8252 42.5495L39.9383 42.4743L40.4406 42.249L40.7358 42.08C40.8027 42.0717 40.8383 42.0571 40.8425 42.0362C40.8509 41.9944 40.8384 41.9483 40.805 41.8981L40.9242 41.9547L40.9556 41.961L41.2507 41.7919L41.2634 41.7292L41.1442 41.6726C41.1525 41.7395 41.1462 41.7709 41.1253 41.7667C41.1086 41.7416 41.0898 41.7269 41.0688 41.7227C41.0521 41.6976 41.0312 41.6934 41.0061 41.7101C40.981 41.7268 40.9663 41.7456 40.9621 41.7665L40.8741 41.8793L40.805 41.8981L40.7486 41.8541C40.6984 41.8875 40.6711 41.9146 40.6669 41.9355C40.6585 41.9774 40.6334 41.9941 40.5915 41.9857L40.5475 42.0421C40.56 42.0881 40.5245 42.1027 40.4408 42.0859C40.4366 42.1068 40.4198 42.1361 40.3905 42.1737C40.3654 42.1904 40.3444 42.1862 40.3277 42.161C40.311 42.1359 40.2901 42.1317 40.265 42.1484C40.2399 42.1651 40.2169 42.1714 40.1959 42.1672L40.0201 42.2297L40.0075 42.2924C40.0033 42.3133 39.9886 42.3321 39.9635 42.3489C39.9593 42.3698 39.9488 42.3677 39.9321 42.3425C39.9154 42.3174 39.882 42.3216 39.8317 42.355C39.8066 42.3717 39.7836 42.3779 39.7627 42.3737C39.7627 42.3737 39.7501 42.3821 39.725 42.3988C39.725 42.3988 39.7333 42.4113 39.75 42.4364L39.7437 42.4678L39.7123 42.4615C39.5994 42.4823 39.5408 42.5031 39.5365 42.524C39.5323 42.5449 39.5072 42.5616 39.4612 42.5741C39.4403 42.5699 39.4193 42.5657 39.3984 42.5615C39.3942 42.5824 39.3712 42.5887 39.3294 42.5802C39.2791 42.6137 39.254 42.6304 39.254 42.6304C39.2749 42.6346 39.2916 42.6597 39.3041 42.7057C39.3208 42.7309 39.3522 42.7372 39.3982 42.7247L39.6557 42.5807ZM39.4687 41.5638C39.5441 41.5136 39.5818 41.4886 39.5818 41.4886L39.8207 41.1124L39.8334 41.0496L39.7584 40.7734C39.7501 40.7064 39.7209 40.6897 39.6706 40.7231C39.4905 40.8609 39.3732 41.0114 39.3186 41.1745C39.3268 41.3502 39.358 41.4653 39.4123 41.5198C39.4081 41.5407 39.4269 41.5553 39.4687 41.5638ZM41.5253 43.0223C41.4919 42.9721 41.4752 42.947 41.4752 42.947L41.4061 42.9657L41.3118 43.1099L41.3432 43.1162L41.5253 43.0223ZM40.729 42.4377C40.7751 42.4252 40.8232 42.4022 40.8735 42.3688C40.9237 42.3354 40.9949 42.3062 41.087 42.2812L41.175 42.1684L41.1059 42.1871L40.704 42.4C40.704 42.4 40.7019 42.4105 40.6977 42.4314C40.6977 42.4314 40.6872 42.4293 40.6663 42.4251L40.729 42.4377ZM39.8839 40.7986C39.8965 40.7359 39.8945 40.692 39.8778 40.6668C39.8778 40.6668 39.8611 40.6417 39.8277 40.5915L39.8151 40.6542L39.8212 40.786L39.8776 40.83L39.8839 40.7986ZM41.4624 43.1729C41.4875 43.1562 41.6194 43.0957 41.858 42.9914C41.8789 42.9956 41.8914 42.9872 41.8957 42.9663L41.902 42.935C41.8601 42.9265 41.8371 42.9328 41.8329 42.9537L41.6508 43.0476L41.431 43.1666L41.4247 43.1979L41.4624 43.1729ZM40.7299 41.785C40.7341 41.7641 40.7341 41.7641 40.7299 41.785C40.7508 41.7892 40.7633 41.7809 40.7676 41.76L40.9497 41.6661C40.9539 41.6451 40.9664 41.6368 40.9874 41.641L40.9623 41.6033C40.8618 41.6701 40.7885 41.7098 40.7425 41.7223L40.7299 41.785ZM41.7828 42.8783C41.833 42.8449 41.8582 42.8282 41.8582 42.8282L41.8394 42.7592C41.8185 42.7549 41.7829 42.7695 41.7327 42.803L41.7828 42.8783ZM42.1091 42.8787C42.1133 42.8578 42.105 42.8453 42.0841 42.8411C42.0632 42.8368 42.0276 42.8514 41.9773 42.8848L42.0024 42.9225L42.1091 42.8787ZM41.3884 42.0808L41.6082 41.9618C41.6082 41.9618 41.6334 41.9451 41.6836 41.9117L41.6209 41.8991L41.3634 42.0431L41.3571 42.0745L41.3884 42.0808ZM41.0627 41.5909L41.2888 41.4406C41.3098 41.4448 41.3223 41.4364 41.3265 41.4155L41.2952 41.4092L41.0377 41.5532L41.0314 41.5846L41.0627 41.5909ZM42.1845 42.8286C42.2054 42.8328 42.218 42.8245 42.2222 42.8036L42.3666 42.7347L42.3729 42.7034L42.3416 42.697L42.1658 42.7596L42.1845 42.8286ZM42.1847 42.6655C42.2183 42.6069 42.2685 42.5735 42.3355 42.5652C42.3397 42.5443 42.3522 42.536 42.3731 42.5402L42.3167 42.4962C42.2246 42.5212 42.1535 42.5504 42.1032 42.5838C42.0823 42.5796 42.0698 42.5879 42.0656 42.6088C42.0613 42.6297 42.0467 42.6486 42.0215 42.6653L42.1157 42.6842L42.147 42.6905L42.1847 42.6655ZM41.7967 41.8366C41.8469 41.8032 41.8825 41.7886 41.9034 41.7928L41.9097 41.7614L41.8407 41.7801C41.8407 41.7801 41.8156 41.7969 41.7653 41.8303L41.7967 41.8366ZM42.3858 42.4774C42.4067 42.4817 42.4423 42.4671 42.4925 42.4337C42.4716 42.4294 42.4612 42.4273 42.4612 42.4273C42.4654 42.4064 42.4675 42.396 42.4675 42.396C42.4256 42.3875 42.4005 42.4042 42.3921 42.4461C42.3712 42.4419 42.3586 42.4502 42.3544 42.4711C42.3753 42.4753 42.3858 42.4774 42.3858 42.4774ZM41.3261 41.7418C41.4684 41.6834 41.5668 41.6271 41.6213 41.5728L41.7343 41.4976C42.0735 41.3265 42.2723 41.2033 42.331 41.1281C42.3561 41.1114 42.3603 41.0905 42.3436 41.0654C42.3521 41.0235 42.3458 41.0005 42.3249 40.9963C42.3291 40.9754 42.3208 40.9628 42.2998 40.9586L42.3062 40.9272L42.2748 40.9209L42.2622 40.9837L42.2558 41.015C42.214 41.0066 42.191 41.0129 42.1868 41.0338L41.452 41.4408L41.4457 41.4721L41.4771 41.4785L41.5461 41.4597L41.5335 41.5225C41.5251 41.5643 41.5104 41.5831 41.4895 41.5789L41.4581 41.5726C41.366 41.5975 41.3096 41.6079 41.2886 41.6037L41.2446 41.6602C41.2656 41.6644 41.2844 41.679 41.3011 41.7042C41.3178 41.7293 41.3261 41.7418 41.3261 41.7418ZM41.5777 41.3029C41.6615 41.2109 41.762 41.1441 41.8792 41.1024L41.8855 41.071L41.8541 41.0647C41.8541 41.0647 41.7536 41.1315 41.5526 41.2652C41.5526 41.2652 41.5505 41.2756 41.5463 41.2965C41.5463 41.2965 41.5359 41.2944 41.515 41.2902L41.5777 41.3029ZM42.1986 41.6237C42.3242 41.5402 42.387 41.4984 42.387 41.4984L42.3933 41.4671L42.362 41.4607L42.1799 41.5547L42.1735 41.586L42.1986 41.6237ZM43.0075 42.1456C43.0577 42.1122 43.0829 42.0955 43.0829 42.0955C43.0913 42.0537 43.106 42.0349 43.1269 42.0391L43.2713 41.9702L43.2526 41.9012L43.1961 41.8572C43.1543 41.8488 43.1292 41.8655 43.1208 41.9073C43.1081 41.97 43.06 41.993 42.9763 41.9761L42.9323 42.0326L43.0075 42.1456ZM43.001 42.3402L43.045 42.2837L43.2648 42.1648C43.4406 42.0479 43.5286 41.9894 43.5286 41.9894C43.6249 41.9435 43.7128 41.885 43.7924 41.814L43.805 41.7513L43.7423 41.7386C43.6418 41.8054 43.5769 41.8577 43.5475 41.8953L43.5162 41.889C43.5077 41.9308 43.4407 41.9935 43.3151 42.077L42.9822 42.2711C42.9613 42.2669 42.9488 42.2752 42.9445 42.2962C42.9403 42.3171 42.9257 42.3359 42.9005 42.3526C42.9215 42.3568 42.9298 42.3694 42.9256 42.3903L43.001 42.3402ZM41.9613 40.6946L42.4512 40.3689L42.4952 40.3125L42.4638 40.3061C42.4638 40.3061 42.4534 40.304 42.4325 40.2998C42.4325 40.2998 42.4304 40.3103 42.4262 40.3312C42.4262 40.3312 42.3257 40.398 42.1247 40.5316L41.8986 40.682C41.8776 40.6778 41.8651 40.6861 41.8609 40.707L41.8922 40.7133L41.9613 40.6946ZM42.9083 41.179L42.9146 41.1477L42.8833 41.1413L42.7388 41.2102L42.7325 41.2416L42.7639 41.2479L42.9083 41.179ZM43.422 41.87C43.4305 41.8282 43.4451 41.8094 43.466 41.8136C43.579 41.7928 43.6418 41.7511 43.6545 41.6883L43.6608 41.6569L43.6294 41.6506L43.5164 41.7258C43.4955 41.7216 43.4829 41.7299 43.4787 41.7509C43.4745 41.7718 43.4724 41.7822 43.4724 41.7822C43.4514 41.778 43.4033 41.801 43.3279 41.8511L43.2902 41.8761L43.3467 41.9201L43.422 41.87ZM42.4754 41.0592L42.5571 40.9778L42.5948 40.9527C42.6576 40.9653 42.7204 40.9236 42.7832 40.8274C42.8084 40.8107 42.8482 40.7752 42.9026 40.7209C42.978 40.6708 43.0492 40.6416 43.1161 40.6333L43.1601 40.5769C43.1601 40.5769 43.1434 40.5518 43.11 40.5015L43.0473 40.4889C42.9928 40.5432 42.9572 40.5578 42.9405 40.5327L42.9091 40.5264C42.9007 40.5682 42.8714 40.6058 42.8211 40.6392C42.7709 40.6726 42.7458 40.6893 42.7458 40.6893C42.7039 40.6809 42.6997 40.7018 42.7331 40.7521L42.7519 40.8211L42.6641 40.7708L42.6013 40.7582L42.6201 40.8272L42.6388 40.8963L42.6074 40.89L42.551 40.846C42.5637 40.7832 42.5344 40.7665 42.4632 40.7957L42.4192 40.8521C42.3941 40.8688 42.3773 40.898 42.3689 40.9399L42.4441 41.0529L42.4754 41.0592ZM40.0022 41.508C40.3287 41.3996 40.5673 41.2953 40.7181 41.1951C40.6469 41.2243 41.0991 40.978 42.0746 40.4563L42.5959 40.1369C42.667 40.1077 42.7424 40.0576 42.822 39.9865C42.9267 39.8988 43.0251 39.8425 43.1171 39.8175C43.1674 39.7841 43.1988 39.736 43.2115 39.6732C43.2115 39.6732 43.2366 39.6565 43.2868 39.6231C43.3748 39.5103 43.4314 39.4455 43.4565 39.4288C43.511 39.3745 43.5068 39.341 43.4441 39.3284C43.3395 39.3073 43.3249 39.2717 43.4003 39.2216L43.4443 39.1652L43.4569 39.1025C43.4569 39.1025 43.4465 39.1004 43.4256 39.0962C43.4256 39.0962 43.4235 39.1066 43.4193 39.1275L43.0611 39.4471C43.0611 39.4471 43.0569 39.468 43.0485 39.5099L43.0422 39.5412L42.8098 39.7229L42.747 39.7103L42.7533 39.6789L42.7973 39.6225L42.8036 39.5911L42.7723 39.5848C42.7681 39.6057 42.745 39.612 42.7032 39.6036L42.7723 39.5848L42.8163 39.5284L43.4195 38.9644L43.8906 38.5696C44.0038 38.44 44.0751 38.3021 44.1045 38.1557C44.1005 38.0678 44.0671 38.0175 44.0043 38.0049C43.6906 37.9418 43.4585 37.9059 43.3079 37.8973C43.1615 37.8679 42.9167 37.8404 42.5737 37.8148L42.216 37.8081C42.1281 37.8122 42.0653 37.8539 42.0276 37.9334C42.0191 37.9752 41.9876 38.0777 41.933 38.2408C41.8784 38.4039 41.805 38.5523 41.7128 38.6861C41.6457 38.8031 41.5683 38.8637 41.4804 38.8678L41.3046 38.9303C41.2962 38.9721 41.292 38.993 41.292 38.993L41.3857 39.3383C41.4525 39.4388 41.4461 39.5246 41.3665 39.5956L41.1718 39.7522C41.1006 39.7814 41.0043 39.8273 40.8829 39.8899C40.7866 39.9358 40.6799 39.9796 40.5627 40.0213C40.3785 40.0713 40.2005 40.1987 40.0287 40.4035C40.0036 40.4202 39.9847 40.4599 39.9721 40.5226C39.9637 40.5645 39.972 40.6314 39.997 40.7235L39.9458 41.464C39.9374 41.5058 39.9562 41.5204 40.0022 41.508ZM42.99 41.0976C43.0318 41.106 43.0674 41.0914 43.0967 41.0538C43.1261 41.0161 43.1324 40.9848 43.1157 40.9596C43.1742 40.9932 43.2328 40.9723 43.2915 40.8971C43.3124 40.9013 43.325 40.893 43.3292 40.8721C43.3334 40.8511 43.3481 40.8323 43.3732 40.8156C43.3481 40.8323 43.325 40.8386 43.3041 40.8344C43.2832 40.8302 43.2706 40.8385 43.2664 40.8594C43.2664 40.8594 43.2162 40.8928 43.1157 40.9596C43.0821 41.0182 43.0319 41.0516 42.9649 41.0599L42.9586 41.0912L42.99 41.0976ZM43.5606 41.5062C43.5606 41.5062 43.6234 41.4644 43.749 41.3809C43.7783 41.3433 43.8433 41.2911 43.9438 41.2243L44.0191 41.1742L43.925 41.1552L43.8246 41.1676L43.5105 41.4308L43.5041 41.4622C43.5041 41.4622 43.502 41.4727 43.4978 41.4936C43.5187 41.4978 43.5397 41.502 43.5606 41.5062ZM44.0374 41.5696C44.0793 41.578 44.1128 41.5738 44.1379 41.5571L44.3326 41.4005L44.408 41.3504L44.3579 41.275L44.3202 41.3001L44.2322 41.4129L44.1631 41.4317L44.0815 41.5131L44.0374 41.5696ZM43.4736 40.8032C43.7877 40.54 43.9804 40.3938 44.0515 40.3646C44.0557 40.3437 44.0683 40.3354 44.0892 40.3396L44.0265 40.327L43.8757 40.4272L43.4172 40.7592L43.4046 40.8219L43.4296 40.8596L43.4736 40.8032ZM44.0819 41.1868C44.1112 41.1492 44.1363 41.1325 44.1572 41.1367C44.2033 41.1242 44.2284 41.1075 44.2326 41.0866C44.2955 40.9904 44.3521 40.9257 44.4023 40.8923C44.4232 40.8965 44.4379 40.8777 44.4463 40.8358L44.3899 40.7918L44.2391 40.892C44.1386 40.9589 44.0884 40.9923 44.0884 40.9923C44.013 41.0424 44.0004 41.1051 44.0505 41.1805L44.0819 41.1868ZM43.2243 39.4473L43.2369 39.3846C43.2327 39.4055 43.2202 39.4139 43.1992 39.4097C43.2035 39.3887 43.2035 39.3887 43.1992 39.4097C43.1992 39.4097 43.149 39.4431 43.0485 39.5099L43.2243 39.4473ZM44.6091 41.1624C44.63 41.1666 44.6404 41.1687 44.6404 41.1687C44.6446 41.1478 44.6467 41.1373 44.6467 41.1373C44.651 41.1164 44.6426 41.1038 44.6217 41.0996L44.5777 41.1561L44.4333 41.2249L44.4206 41.2876L44.4834 41.3003L44.6091 41.1624ZM44.4522 41.1308C44.5025 41.0974 44.5485 41.0849 44.5903 41.0933L44.5966 41.0619L44.5653 41.0556L44.4271 41.0931L44.4208 41.1245L44.4522 41.1308ZM44.8038 41.0057L44.7787 40.968L44.7097 40.9868L44.7284 41.0558L44.8038 41.0057ZM43.2355 40.5268C43.2355 40.5268 43.3234 40.4683 43.4993 40.3514C43.5495 40.318 43.5537 40.2971 43.5119 40.2886C43.5119 40.2886 43.5224 40.2908 43.5433 40.295C43.5475 40.2741 43.5496 40.2636 43.5496 40.2636C43.5705 40.2678 43.581 40.2699 43.581 40.2699C43.6396 40.1947 43.6899 40.1613 43.7317 40.1697C43.782 40.1363 43.8092 40.1091 43.8134 40.0882L43.9265 40.013C43.9307 39.9921 43.9579 39.965 44.0082 39.9316C43.9788 39.9692 44.1108 39.8543 44.404 39.5869C44.4291 39.5702 44.4563 39.543 44.4856 39.5054C44.5359 39.472 44.5819 39.4595 44.6238 39.4679L44.6614 39.4429C44.6699 39.4011 44.6992 39.3634 44.7495 39.33L44.8815 39.1608L44.8878 39.1294C44.8669 39.1252 44.8543 39.1335 44.8501 39.1544L44.7307 39.261L44.6617 39.2797L44.6743 39.217C44.733 39.1417 44.7665 39.0832 44.7749 39.0414L44.7812 39.01C44.7812 39.01 44.7708 39.0079 44.7499 39.0037C44.7499 39.0037 44.7478 39.0142 44.7436 39.0351C44.6933 39.0685 44.6535 39.104 44.6242 39.1416C44.5948 39.1792 44.5655 39.2168 44.5362 39.2545L44.5299 39.2858L44.1844 39.5427C44.1341 39.5761 44.1048 39.6137 44.0964 39.6555L44.0147 39.737C43.9393 39.7871 43.8912 39.8101 43.8702 39.8059L43.8075 39.7932C43.7824 39.8099 43.73 39.8538 43.6504 39.9248C43.5751 39.9749 43.5269 40.0523 43.5058 40.1569L43.4618 40.2133L43.4431 40.1442L43.4494 40.1128C43.4285 40.1086 43.4159 40.117 43.4117 40.1379C43.3949 40.2216 43.3551 40.2571 43.2923 40.2444C43.2714 40.2402 43.2358 40.2548 43.1856 40.2882C43.2441 40.3218 43.2587 40.3574 43.2294 40.395C43.2042 40.4117 43.1896 40.4305 43.1854 40.4514L43.1727 40.5141L43.2355 40.5268ZM44.5657 40.7293C44.6159 40.6959 44.6432 40.6687 44.6474 40.6478C44.6934 40.6353 44.7458 40.5915 44.8044 40.5162C44.8253 40.5204 44.8253 40.5204 44.8044 40.5162C44.8086 40.4953 44.8107 40.4848 44.8107 40.4848L44.7794 40.4785C44.704 40.5286 44.6349 40.6018 44.572 40.6979C44.5511 40.6937 44.5385 40.7021 44.5343 40.723L44.5657 40.7293ZM45.3383 40.1341C45.3886 40.1007 45.4137 40.084 45.4137 40.084L45.3823 40.0777L45.3573 40.04C45.3615 40.0191 45.3532 40.0065 45.3322 40.0023L45.3259 40.0337L45.3196 40.065L45.3383 40.1341ZM45.2145 38.8035L45.3152 38.6279C45.3194 38.607 45.311 38.5944 45.2901 38.5902L45.2587 38.5839C45.2419 38.6675 45.2167 38.7386 45.1832 38.7972L45.2082 38.8348L45.2145 38.8035ZM44.4138 36.7817C44.418 36.7608 44.4097 36.7482 44.3887 36.744L44.1504 36.6307L44.1441 36.6621L44.05 36.6431L44.0123 36.6682L44.075 36.6808C44.1169 36.6892 44.1461 36.706 44.1628 36.7311L44.3824 36.7754L44.4138 36.7817ZM44.9536 36.6945C44.8993 36.64 44.8199 36.6023 44.7153 36.5812C44.6149 36.5393 44.5438 36.5141 44.502 36.5056L44.295 36.3987L44.2763 36.3296L44.3517 36.2795L44.4144 36.2922L44.8848 36.5501C44.9057 36.5543 44.9245 36.5689 44.9412 36.5941C44.9788 36.6234 45.0081 36.6402 45.029 36.6444L45.0477 36.7134L44.985 36.7008L44.9536 36.6945ZM45.9211 55.332C45.8165 55.311 45.7308 55.2502 45.664 55.1497L45.5448 55.0931C45.3984 55.0636 45.2835 54.986 45.1999 54.8604C45.1205 54.8227 45.0557 54.7661 45.0056 54.6907C44.9346 54.6111 44.8363 54.5587 44.7109 54.5335C44.6857 54.5502 44.6439 54.5417 44.5854 54.5082C44.5268 54.4747 44.4767 54.4537 44.4348 54.4453L44.0649 54.1749C43.9564 53.9572 43.8165 53.7876 43.6451 53.6661C43.5322 53.5781 43.4444 53.5277 43.3817 53.5151C43.2771 53.4941 43.2166 53.4166 43.2 53.2827C43.1708 53.2115 43.0601 53.1131 42.8678 52.9873C42.7131 52.8909 42.5606 52.6752 42.4105 52.3403C42.3813 52.2692 42.3209 52.0285 42.2294 51.6184C42.2128 51.4845 42.2255 51.3673 42.2675 51.267L42.2361 51.2607L42.3997 50.9345C42.4752 50.7756 42.5193 50.6648 42.5319 50.6021L42.6452 50.3638C42.6954 50.3304 42.7394 50.2739 42.7772 50.1945C42.8149 50.115 42.8359 50.0649 42.8401 50.0439C42.79 49.9686 42.7796 49.9121 42.809 49.8745C42.8634 49.8201 42.8928 49.7825 42.897 49.7616C42.9473 49.6194 43.0249 49.5045 43.1296 49.4167C43.226 49.2621 43.3288 49.076 43.4378 48.8586C43.4798 48.7582 43.5741 48.614 43.7208 48.4259C43.7794 48.3507 43.9576 48.1145 44.2551 47.7175C44.36 47.5209 44.4564 47.3663 44.5444 47.2534C44.6366 47.1196 44.7142 47.0047 44.777 46.9085C44.9153 46.7623 45.0494 46.5826 45.1794 46.3693C45.305 46.2858 45.3846 46.1604 45.4183 45.9931L45.475 45.8739L45.6133 45.6733C45.6342 45.6775 45.6572 45.6713 45.6823 45.6546C45.7075 45.6378 45.7221 45.619 45.7263 45.5981L45.808 45.5166C46.0427 45.2157 46.1789 45.0255 46.2167 44.9461C46.3298 44.8165 46.4304 44.6953 46.5184 44.5825C46.6106 44.4487 46.686 44.3442 46.7447 44.269L47.0967 43.8176C47.1302 43.759 47.1952 43.6524 47.2917 43.4977C47.3881 43.3431 47.4908 43.2114 47.5997 43.1028C47.7421 42.9356 47.8364 42.7914 47.8826 42.6701L48.1719 42.2061C48.2515 42.135 48.308 42.0703 48.3416 42.0117C48.3793 41.9323 48.4129 41.8738 48.4422 41.8361C48.4549 41.7734 48.5052 41.6856 48.5932 41.5728C48.6392 41.5603 48.656 41.531 48.6435 41.485C48.6561 41.4222 48.6541 41.3783 48.6374 41.3532L48.4744 41.1898C48.4786 41.1689 48.4724 41.1459 48.4557 41.1207C48.4641 41.0789 48.4809 41.0496 48.506 41.0329C48.5271 40.9284 48.5209 40.851 48.4875 40.8007L48.5001 40.738L48.5254 40.6125C48.513 40.4577 48.5717 40.3824 48.7014 40.3868C48.7516 40.3534 48.8332 40.3263 48.9462 40.3055C49.2182 40.2515 49.4547 40.1576 49.6557 40.024C49.6976 40.0324 49.7248 40.0053 49.7374 39.9425L50.1337 39.2715C50.163 39.2339 50.1714 39.1921 50.1589 39.146C50.1673 39.1042 50.1883 39.054 50.2219 38.9955C50.2512 38.9579 50.2973 38.891 50.3602 38.7949C50.4482 38.682 50.5382 38.6131 50.6303 38.5881C50.8062 38.4712 51.0091 38.4359 51.2392 38.4822C51.4483 38.5243 51.6031 38.5663 51.7034 38.6083C51.8038 38.6503 51.8957 38.7341 51.9792 38.8597C52.0378 38.8932 52.0942 38.9372 52.1485 38.9917C52.2028 39.0461 52.2593 39.0901 52.3178 39.1237C52.3303 39.1697 52.3741 39.2221 52.4494 39.2807C52.5455 39.3436 52.6124 39.3897 52.65 39.4191L52.8882 39.6955C52.9216 39.7457 52.9696 39.7772 53.0324 39.7898C53.2541 39.7692 53.4362 39.7297 53.5785 39.6713C54.0598 39.5506 54.5118 39.4675 54.9344 39.422C55.2609 39.3136 55.5789 39.2471 55.8886 39.2224C56.1815 39.1725 56.4116 39.1645 56.5789 39.1981L56.7985 39.2423L57.0808 39.2992C57.1018 39.3034 57.1519 39.3244 57.2314 39.3621C57.315 39.379 57.3715 39.423 57.4007 39.4941C57.4174 39.5193 57.4466 39.536 57.4885 39.5445C57.5303 39.5529 57.57 39.5718 57.6076 39.6011C57.6243 39.6262 57.6536 39.643 57.6954 39.6514C57.7163 39.6556 57.7247 39.6682 57.7205 39.6891L57.6891 39.6828C57.6682 39.6786 57.6452 39.6848 57.62 39.7015C57.6158 39.7224 57.6137 39.7329 57.6137 39.7329L57.6325 39.8019L57.5948 39.827L57.6072 39.9274L57.8205 40.003C57.8205 40.003 57.8372 40.0281 57.8706 40.0784C57.8873 40.1035 57.9019 40.1391 57.9144 40.1851C57.9311 40.2102 57.9436 40.2563 57.9519 40.3232C57.9392 40.386 57.9517 40.432 57.9893 40.4613C58.027 40.4907 58.0541 40.5179 58.0708 40.543C58.0917 40.5472 58.1126 40.6058 58.1334 40.7188C58.171 40.7482 58.1981 40.7754 58.2148 40.8005C58.2525 40.8299 58.2796 40.8571 58.2963 40.8822C58.3631 40.9827 58.3651 41.081 58.3022 41.1772C58.277 41.3027 58.2476 41.3947 58.214 41.4532L58.2075 41.6477C58.2116 41.7356 58.1947 41.8193 58.157 41.8987L57.9871 42.2562L57.8487 42.4568L57.786 42.4442C57.7526 42.394 57.7652 42.3312 57.8239 42.256C57.849 42.2393 57.8658 42.21 57.8742 42.1682C57.8868 42.1055 57.8848 42.0615 57.8681 42.0364C57.8556 41.9904 57.8431 41.9443 57.8306 41.8983C57.8181 41.8522 57.7701 41.8208 57.6864 41.804C57.6655 41.7998 57.6508 41.8186 57.6424 41.8604L57.5984 41.9168L57.611 41.8541C57.5943 41.829 57.5923 41.785 57.6049 41.7223L57.4167 41.6844L57.3226 41.6654C57.2641 41.6319 57.1804 41.6151 57.0716 41.6149C56.7536 41.6814 56.5171 41.7209 56.3623 41.7332C56.0903 41.7873 55.6844 41.8579 55.1446 41.9451C54.701 41.9864 54.3767 42.0299 54.1717 42.0756C54.0587 42.0964 53.8892 42.1276 53.6632 42.1691C53.4414 42.1898 53.2552 42.1958 53.1046 42.1872C53.0377 42.1955 52.9582 42.2122 52.8661 42.2371C52.7991 42.2454 52.7196 42.2621 52.6276 42.287C52.4937 42.3036 52.4267 42.3119 52.4267 42.3119C52.2928 42.3285 52.184 42.3283 52.1004 42.3115C52.0752 42.3282 52.0292 42.3407 51.9623 42.349C51.8995 42.3363 51.866 42.3405 51.8618 42.3614L51.7675 42.5056L51.3902 43.0825C51.3316 43.1577 51.2457 43.2601 51.1325 43.3897C51.0445 43.5025 50.967 43.6175 50.8999 43.7345C50.7532 43.9226 50.6463 44.0752 50.5793 44.1923C50.4912 44.3051 50.3928 44.4159 50.2839 44.5245C50.1959 44.6373 50.1058 44.7607 50.0135 44.8944L49.8879 45.0323L49.8815 45.0637L49.9443 45.0763L50.3523 44.9953C50.482 44.9996 50.597 45.0228 50.6974 45.0647C50.735 45.0941 50.8584 45.1298 51.0675 45.1719C51.1303 45.1845 51.1658 45.2243 51.174 45.2913C51.1908 45.3164 51.22 45.3332 51.2618 45.3416C51.4374 45.4422 51.5461 45.4967 51.588 45.5052L51.5753 45.5679L51.544 45.5616C51.5231 45.5574 51.5105 45.5657 51.5063 45.5866C51.5021 45.6076 51.4895 45.6159 51.4686 45.6117C51.4895 45.6159 51.4979 45.6285 51.4937 45.6494C51.4894 45.6703 51.4978 45.6829 51.5187 45.6871L51.732 45.7627L51.7634 45.769L51.8699 45.8883L51.7318 45.9258C51.6481 45.909 51.5937 45.9089 51.5686 45.9256L51.5372 45.9193C51.533 45.9402 51.5414 45.9528 51.5623 45.957L51.6501 46.0073L51.9638 46.0705C52.0056 46.0789 52.0642 46.1124 52.1394 46.1711C52.1602 46.2841 52.1998 46.3573 52.2583 46.3909L52.4403 46.4602C52.4988 46.4937 52.5238 46.5314 52.5154 46.5732C52.5112 46.5941 52.4986 46.6025 52.4777 46.5983L52.2394 46.485L52.1767 46.4724C52.1976 46.4766 52.2059 46.4891 52.2017 46.5101C52.21 46.577 52.2413 46.6377 52.2956 46.6922C52.3751 46.7299 52.4336 46.7635 52.4712 46.7928L52.703 47.1006C52.703 47.1006 52.7009 47.1111 52.6967 47.132C52.6967 47.132 52.7072 47.1341 52.7281 47.1383L52.634 47.1194C52.6382 47.0984 52.6298 47.0859 52.6089 47.0817C52.588 47.0775 52.5775 47.0754 52.5775 47.0754C52.5735 46.9875 52.5568 46.9624 52.5274 47C52.5023 47.0167 52.4793 47.0229 52.4584 47.0187L52.4645 47.1505L52.5961 47.3076C52.5961 47.3076 52.594 47.318 52.5898 47.339C52.6065 47.3641 52.6253 47.3787 52.6462 47.383C52.6044 47.3745 52.5667 47.3452 52.5333 47.2949L52.502 47.2886C52.502 47.2886 52.481 47.2844 52.4392 47.276L52.4516 47.3764C52.6105 47.4519 52.715 47.5274 52.7651 47.6028L52.8778 47.8539L52.9279 47.9293C52.9655 47.9586 52.9592 47.99 52.9089 48.0234C52.8838 48.0401 52.8503 48.0443 52.8085 48.0358L52.6392 47.9038L52.3759 47.7529C52.3006 47.6942 52.2734 47.7214 52.2942 47.8344L52.2879 47.8657L52.2628 47.828C52.2503 47.782 52.2001 47.761 52.1123 47.7651L51.1269 47.7952L50.2043 47.838L49.9344 47.8816C49.6039 47.9021 49.2859 47.9142 48.9805 47.918C48.8717 47.9179 48.7608 47.9282 48.6478 47.949C48.539 47.9488 48.4094 47.9445 48.2588 47.9359C48.2169 47.9275 48.1395 47.9337 48.0265 47.9544C47.9177 47.9543 47.8111 47.9437 47.7065 47.9227L47.5998 47.9665C47.4362 48.2382 47.3147 48.4096 47.2351 48.4806L47.0781 48.6122C46.902 48.8379 46.7072 49.1033 46.4934 49.4085C46.4054 49.5213 46.3132 49.6551 46.2168 49.8098C46.1455 49.9477 46.0407 50.0899 45.9024 50.2361C45.5754 50.7796 45.3741 51.1308 45.2986 51.2897C45.2609 51.3691 45.221 51.459 45.179 51.5594C45.1413 51.6388 45.1098 51.7413 45.0845 51.8668C45.0468 51.9462 45.0718 51.9839 45.1597 51.9798C45.2308 51.9506 45.2873 51.9402 45.3292 51.9487C45.3961 51.9404 45.44 51.9383 45.461 51.9425L45.4923 51.9489C45.4714 51.9446 45.4589 51.953 45.4546 51.9739L45.1094 52.0676C45.0884 52.0634 45.0654 52.0696 45.0403 52.0864C45.0403 52.0864 45.0298 52.0842 45.0089 52.08L45.1344 52.1053L45.3917 52.1245L45.4544 52.1371L45.4168 52.1621L45.1155 52.1994C45.0485 52.2077 45.0004 52.2306 44.971 52.2683C44.9459 52.285 44.9375 52.3268 44.9458 52.3937C44.9416 52.4147 44.9374 52.4356 44.9331 52.4565C44.9541 52.4607 44.9624 52.4733 44.9582 52.4942C44.9498 52.536 44.9874 52.5653 45.0711 52.5822L45.3283 52.6013C45.3953 52.593 45.4727 52.5869 45.5606 52.5828C45.6735 52.562 45.7823 52.5622 45.8869 52.5832L45.9496 52.5958C45.9706 52.6001 45.9915 52.6043 46.0124 52.6085C46.0542 52.6169 46.0835 52.6337 46.1002 52.6588C46.167 52.7593 46.236 52.7949 46.3071 52.7657L47.3428 52.6478L47.7822 52.5731L47.8449 52.5857C47.8867 52.5941 47.9537 52.5858 48.0458 52.5609C48.1378 52.5359 48.2278 52.5213 48.3157 52.5173C48.3617 52.5048 48.4308 52.486 48.5229 52.461C48.6401 52.4194 48.753 52.3986 48.8618 52.3987C48.8827 52.4029 49.0292 52.378 49.3012 52.324C49.4351 52.3074 49.5377 52.2845 49.6088 52.2553C49.7009 52.2303 49.7804 52.2137 49.8474 52.2054C50.0189 52.2182 50.1067 52.2141 50.111 52.1932L50.155 52.1368C50.1759 52.141 50.1842 52.1536 50.18 52.1745C50.1758 52.1954 50.1737 52.2058 50.1737 52.2058C50.2491 52.1557 50.2783 52.1725 50.2615 52.2562C50.2782 52.2813 50.297 52.2959 50.3179 52.3002C50.3597 52.3086 50.3828 52.3023 50.387 52.2814L50.4183 52.2877L50.4811 52.3004L50.4874 52.269L50.5 52.2063C50.5042 52.1853 50.5168 52.177 50.5377 52.1812L50.5314 52.2126L50.5125 52.3067C50.5125 52.3067 50.4873 52.3234 50.4371 52.3568L50.4245 52.4195C50.4202 52.4404 50.416 52.4614 50.4118 52.4823C50.4327 52.4865 50.4411 52.499 50.4369 52.52C50.4536 52.5451 50.5079 52.5995 50.5998 52.6833C50.6208 52.6875 50.6291 52.7001 50.6249 52.721C50.6749 52.9052 50.7312 53.0036 50.794 53.0162C50.8149 53.0204 50.8274 53.0121 50.8316 52.9911C50.8568 52.9744 50.8798 52.9682 50.9007 52.9724L50.9384 52.9473C50.9384 52.9473 50.9363 52.9578 50.9321 52.9787C50.953 52.9829 50.9739 52.9871 50.9948 52.9913L50.9885 53.0227L50.9632 53.1482C50.9842 53.1524 51.0197 53.1378 51.07 53.1044C51.1202 53.071 51.1475 53.0438 51.1517 53.0229C51.1517 53.0229 51.1538 53.0125 51.158 52.9916C51.1831 52.9749 51.1978 52.956 51.202 52.9351C51.2229 52.9393 51.2313 52.9519 51.227 52.9728C51.2228 52.9937 51.2312 53.0063 51.2521 53.0105L51.2458 53.0419C51.1955 53.0753 51.1745 53.1255 51.1828 53.1924C51.1995 53.2175 51.2016 53.2615 51.1889 53.3242C51.2097 53.4372 51.2661 53.4812 51.3582 53.4562C51.4252 53.4479 51.4775 53.4585 51.5151 53.4878C51.561 53.5841 51.5399 53.6886 51.4519 53.8015C51.3556 53.8474 51.3095 53.9143 51.3136 54.0021C51.3177 54.09 51.3176 54.1444 51.3134 54.1653L51.2502 54.479L51.2125 54.5041C51.2125 54.5041 51.2021 54.502 51.1812 54.4978C51.1603 54.4935 51.1519 54.481 51.1561 54.4601C51.0976 54.4265 51.0642 54.3763 51.0559 54.3093C51.0434 54.2633 51.0246 54.2486 50.9995 54.2653C50.8906 54.374 50.7273 54.4281 50.5098 54.4279C50.3968 54.4486 50.2629 54.4652 50.108 54.4776C49.9741 54.4941 49.8277 54.519 49.6687 54.5523C49.5348 54.5689 49.3862 54.6043 49.2229 54.6584L49.1916 54.6521C49.154 54.6228 49.11 54.6248 49.0598 54.6582C49.0095 54.6916 48.9739 54.7062 48.953 54.702L48.9153 54.7271L48.7899 54.7018C48.7563 54.7603 48.7061 54.7938 48.6391 54.802C48.5722 54.8103 48.5282 54.8124 48.5073 54.8081L48.3128 54.8016C48.1789 54.8182 48.0679 54.8829 47.9799 54.9957L47.9486 54.9894C47.8858 54.9768 47.7979 54.9809 47.685 55.0016C47.572 55.0224 47.482 55.037 47.415 55.0452L47.1388 55.1202C47.1179 55.116 47.0823 55.1306 47.0321 55.164C46.9693 55.1514 46.938 55.145 46.938 55.145L46.8752 55.1324C46.8125 55.1198 46.7351 55.126 46.643 55.1509C46.5467 55.1968 46.4651 55.2239 46.3981 55.2322L46.2537 55.3011L46.0152 55.351L45.9211 55.332ZM45.485 52.7961L45.5604 52.746L45.4976 52.7333C45.4349 52.7207 45.3888 52.7332 45.3595 52.7708L45.3218 52.7959L45.3846 52.8085L45.485 52.7961ZM44.1455 50.0456L44.2021 49.9264C44.2063 49.9055 44.198 49.893 44.177 49.8888L44.1707 49.9201C44.1456 49.9368 44.1267 49.9765 44.1141 50.0393L44.1455 50.0456ZM45.7926 52.7274C45.8971 52.7485 45.9724 52.7528 46.0185 52.7403L46.0499 52.7466L46.0248 52.7089L45.7926 52.7274L45.7612 52.7211C45.7612 52.7211 45.7591 52.7316 45.7549 52.7525C45.7758 52.7567 45.7884 52.7483 45.7926 52.7274ZM44.3971 49.6066C44.4473 49.5732 44.4787 49.5251 44.4914 49.4624L44.4977 49.431L44.4663 49.4247L44.3783 49.5376L44.3657 49.6003L44.3971 49.6066ZM48.0944 53.7784C48.1238 53.7408 48.1489 53.7241 48.1698 53.7283C48.1907 53.7325 48.2137 53.7263 48.2389 53.7096L48.6155 53.6222C48.6783 53.6348 48.7557 53.6286 48.8477 53.6036L48.8917 53.5472L48.8227 53.566C48.6051 53.5657 48.4377 53.5864 48.3205 53.6281C48.2703 53.6615 48.1991 53.6907 48.1071 53.7157C48.0861 53.7115 48.0715 53.7303 48.0631 53.7721L48.0944 53.7784ZM48.2144 53.1824C48.3525 53.1449 48.4885 53.1179 48.6225 53.1013C48.7564 53.0847 48.8693 53.064 48.9614 53.039L49.0305 53.0202C48.9886 53.0118 48.9677 53.0076 48.9677 53.0076L48.5347 53.051C48.4886 53.0635 48.43 53.0843 48.3589 53.1135C48.3128 53.126 48.2542 53.1468 48.1831 53.176L48.1517 53.1697L48.1831 53.176L48.2144 53.1824ZM49.3821 52.8952C49.5369 52.8828 49.6624 52.8537 49.7587 52.8078L49.8842 52.833L49.7337 52.7701C49.5914 52.8285 49.4763 52.8597 49.3884 52.8638C49.3884 52.8638 49.3863 52.8742 49.3821 52.8952C49.3821 52.8952 49.3716 52.8931 49.3507 52.8888L49.3821 52.8952ZM57.5102 42.1928L57.5228 42.1301C57.5355 42.0674 57.5543 42.0276 57.5795 42.0109L57.6108 42.0172L57.5352 42.2305L57.5039 42.2242L57.5102 42.1928ZM53.8644 57.9105C53.831 57.8602 53.7558 57.8015 53.6387 57.7344C53.6094 57.7721 53.578 57.7657 53.5446 57.7155C53.4066 57.6442 53.3356 57.5646 53.3315 57.4768L53.2753 57.2696L53.2378 57.1315L53.2505 57.0687C53.2589 57.0269 53.2547 56.9934 53.238 56.9683L53.2067 56.962C53.2109 56.9411 53.2005 56.8846 53.1755 56.7925C53.1797 56.7716 53.1756 56.7381 53.1631 56.6921C53.1673 56.6712 53.1862 56.6314 53.2197 56.5729C53.2448 56.5562 53.247 56.4914 53.2262 56.3784C53.2137 56.3323 53.1824 56.326 53.1321 56.3594L53.1258 56.3908C53.1049 56.3866 53.0965 56.374 53.1008 56.3531C53.126 56.2276 53.1345 56.1314 53.1262 56.0645C53.1304 56.0435 53.1158 56.008 53.0824 55.9577L53.0951 55.895L53.1201 55.9327L53.1515 55.939C53.1641 55.8762 53.16 55.8428 53.1391 55.8385C53.1181 55.8343 53.1098 55.8218 53.114 55.8009C53.1266 55.7381 53.1455 55.6984 53.1706 55.6817C53.1748 55.6608 53.1812 55.6294 53.1896 55.5876L53.1959 55.5562L53.1582 55.5813L53.1456 55.644L53.1142 55.6377C53.0975 55.6126 53.0955 55.5686 53.1081 55.5059C53.0956 55.4599 53.1019 55.4285 53.1271 55.4118C53.1313 55.3909 53.1355 55.37 53.1397 55.349L53.1711 55.3554C53.2213 55.3219 53.2485 55.2948 53.2527 55.2739C53.257 55.253 53.2424 55.2174 53.2089 55.1671C53.1965 55.1211 53.1986 55.0562 53.2155 54.9726C53.2323 54.8889 53.2722 54.799 53.3351 54.7029C53.377 54.6025 53.4022 54.5314 53.4106 54.4896C53.44 54.452 53.4714 54.4039 53.505 54.3454C53.5385 54.2869 53.5825 54.2304 53.637 54.1761C53.704 54.059 53.7397 53.9901 53.7439 53.9691L53.7502 53.9378C53.7502 53.9378 53.7398 53.9357 53.7189 53.9315C53.7189 53.9315 53.7167 53.9419 53.7125 53.9628L53.5742 54.1635C53.5155 54.2387 53.482 54.2972 53.4736 54.3391L53.4045 54.3578L53.4172 54.2951C53.4256 54.2532 53.4591 54.1947 53.5178 54.1195C53.5304 54.0567 53.5661 53.9877 53.6247 53.9125C53.6625 53.8331 53.6981 53.7641 53.7317 53.7056C53.7652 53.647 53.7988 53.5885 53.8323 53.53L53.9833 53.2666C54.0042 53.2708 54.0042 53.2708 53.9833 53.2666C53.9875 53.2457 53.9896 53.2352 53.9896 53.2352L54.0022 53.1725C54.0106 53.1306 54.0442 53.0721 54.1029 52.9969L54.1092 52.9655L54.0778 52.9592L54.0338 53.0156L53.9961 53.0407L54.0024 53.0093C54.0024 53.0093 53.992 53.0072 53.9711 53.003C53.9711 53.003 53.9732 52.9925 53.9774 52.9716L53.9711 53.003L53.8391 53.1723L53.8014 53.1973L53.8077 53.1659C53.8245 53.0823 53.8476 53.0216 53.8769 52.984C53.8896 52.9213 53.9085 52.8816 53.9336 52.8649C53.9629 52.8272 53.9923 52.7896 54.0216 52.752L54.0595 52.5638L54.0281 52.5575C54.0072 52.5533 53.9946 52.5616 53.9904 52.5825L53.9214 52.6013C53.9214 52.6013 53.9109 52.5992 53.89 52.595C53.8942 52.574 53.9068 52.5657 53.9277 52.5699C53.9445 52.4862 53.976 52.4382 54.022 52.4257L54.0283 52.3943C54.0661 52.3149 54.1164 52.2271 54.1793 52.1309C54.2421 52.0348 54.2883 51.9679 54.3176 51.9303C54.3763 51.855 54.4098 51.7965 54.4182 51.7547C54.4433 51.738 54.4455 51.7275 54.4245 51.7233C54.4287 51.7024 54.433 51.6815 54.4372 51.6606C54.3953 51.6521 54.3723 51.6584 54.3681 51.6793C54.3681 51.6793 54.343 51.696 54.2927 51.7294L54.3117 51.6353L54.3997 51.5225L54.406 51.4911L54.3746 51.4848C54.3662 51.5266 54.3369 51.5642 54.2866 51.5976L54.2803 51.629C54.2845 51.6081 54.2762 51.5955 54.2553 51.5913L54.3119 51.4721L54.3182 51.4408C54.2973 51.4366 54.2847 51.4449 54.2805 51.4658C54.2303 51.4992 54.1988 51.5473 54.1862 51.61C54.1653 51.6058 54.1527 51.6142 54.1485 51.6351L54.2113 51.6477C54.2113 51.6477 54.2092 51.6582 54.2049 51.6791C54.2049 51.6791 54.2154 51.6812 54.2363 51.6854C54.2154 51.6812 54.2028 51.6896 54.1986 51.7105C54.1401 51.6769 54.1024 51.702 54.0856 51.7856L53.7525 52.1429L53.7588 52.1116L53.9035 51.8795C54.025 51.7082 54.1361 51.5347 54.2367 51.3591L54.5134 50.9578L54.5574 50.9014C54.5155 50.8929 54.4925 50.8992 54.4883 50.9201L54.3563 51.0894L54.3123 51.1458C54.3207 51.104 54.3354 51.0852 54.3563 51.0894L54.7713 50.4874C54.9137 50.3203 55.1107 50.0444 55.3622 49.6598L55.6766 49.2334C55.7688 49.0997 55.8736 48.9576 55.9909 48.8071C56.1124 48.6357 56.2256 48.4518 56.3305 48.2553C56.3767 48.134 56.4291 48.0357 56.4878 47.9605C56.5464 47.8853 56.5925 47.8184 56.6261 47.7598C56.8105 47.4923 56.9384 47.2896 57.0097 47.1516L57.4499 46.4242L57.7832 45.9037C57.9174 45.6696 58.0075 45.4919 58.0537 45.3706L58.1794 45.2327C58.368 44.9443 58.5169 44.6913 58.6259 44.4739C58.6637 44.3945 58.7412 44.2795 58.8586 44.129L59.318 43.1443L59.6323 42.718L59.7832 42.4546L59.9152 42.2853L59.9906 42.2352C60.0032 42.1725 60.0431 42.0826 60.1102 41.9655L60.3553 41.7211C60.3804 41.7044 60.3972 41.6751 60.4056 41.6333C60.4558 41.5999 60.4914 41.5853 60.5123 41.5895C60.5751 41.6021 60.6525 41.5959 60.7445 41.5709L60.7509 41.5396C60.7844 41.481 60.8117 41.3995 60.8328 41.2949C60.8454 41.2322 60.9082 41.1904 61.0212 41.1696C61.063 41.1781 61.0965 41.1739 61.1216 41.1572C61.1467 41.1405 61.1719 41.1238 61.197 41.1071C61.2012 41.0862 61.2284 41.059 61.2787 41.0256C61.2829 41.0047 61.2954 40.9964 61.3164 41.0006L61.3353 40.9065L61.4044 40.8877L61.3667 40.9128L61.3854 40.9818C61.4063 40.9861 61.4168 40.9882 61.4168 40.9882C61.421 40.9672 61.4231 40.9568 61.4231 40.9568C61.4649 40.9652 61.4837 40.9799 61.4795 41.0008L61.5109 41.0071L61.5423 41.0134L61.536 41.0448L61.4103 41.1827L61.3913 41.2768L61.4353 41.2204C61.4395 41.1995 61.4981 41.1786 61.6111 41.1578C61.632 41.1621 61.6739 41.1705 61.7366 41.1831C61.8245 41.179 61.8956 41.1498 61.9501 41.0955L61.9878 41.0705L62.0065 41.1395C61.9981 41.1814 62.0022 41.2148 62.0189 41.24C62.0692 41.2065 62.0943 41.1898 62.0943 41.1898C62.1194 41.1731 62.2137 41.0833 62.3771 40.9203C62.4691 40.8954 62.5298 40.8641 62.5592 40.8264C62.5592 40.8264 62.5696 40.8285 62.5905 40.8328C62.6115 40.837 62.6198 40.8495 62.6156 40.8704C62.6239 40.9374 62.6741 40.9584 62.7661 40.9334C62.7703 40.9125 62.7829 40.9041 62.8038 40.9083L62.7598 40.9648C62.7556 40.9857 62.7409 41.0045 62.7158 41.0212C62.6907 41.0379 62.6865 41.0588 62.7032 41.0839C62.7199 41.1091 62.7596 41.1279 62.8224 41.1406C62.906 41.1574 62.9458 41.1219 62.9417 41.034C62.9502 40.9922 62.9753 40.9755 63.0171 40.9839C63.0798 40.9965 63.1363 40.9862 63.1866 40.9528C63.2326 40.9403 63.287 40.9403 63.3498 40.953C63.4125 40.9656 63.4627 40.9866 63.5003 41.0159C63.5003 41.0159 63.517 41.041 63.5504 41.0913C63.5629 41.1373 63.5419 41.1875 63.4875 41.2418C63.4581 41.2794 63.4413 41.3087 63.4371 41.3296C63.4287 41.3714 63.435 41.3945 63.4559 41.3987L63.4496 41.43L63.3051 41.4989L63.2925 41.5616C63.3802 41.6663 63.4009 41.8337 63.3546 42.0638L63.3041 42.3147C63.2704 42.482 63.1823 42.7037 63.0397 42.9796C62.9893 43.1218 62.9346 43.3393 62.8757 43.6321L62.8378 43.8203C62.7873 44.0713 62.7639 44.3495 62.7677 44.6549C62.78 44.8097 62.7734 45.0586 62.7479 45.4017C62.752 45.4895 62.7351 45.5732 62.6974 45.6526C62.6805 45.7363 62.6742 45.8221 62.6782 45.9099C62.6572 46.0145 62.6465 46.1756 62.6462 46.3931C62.6082 46.6901 62.5868 47.0666 62.582 47.5227L62.537 48.3949L62.4985 49.0727C62.4814 49.3739 62.456 49.6081 62.4223 49.7754C62.3967 50.1185 62.3671 50.3737 62.3335 50.541C62.3292 50.5619 62.3376 50.5744 62.3585 50.5787C62.3332 50.7041 62.3205 50.8757 62.3202 51.0932L62.3514 51.2627C62.3806 51.3339 62.3887 51.5096 62.3758 51.7899C62.3674 51.8317 62.3547 51.8945 62.3379 51.9781C62.3462 52.0451 62.3231 52.1057 62.2686 52.16L62.2874 52.2291L62.3564 52.2103L62.5891 51.8655L62.9034 51.4391L63.1611 51.1319L63.3371 50.9062L63.6262 50.6054L63.8462 50.3232L63.9908 50.0912C64.0201 50.0536 64.0956 49.9491 64.2171 49.7777L64.6258 49.2072C64.6593 49.1486 64.6908 49.1006 64.7201 49.0629C64.7536 49.0044 64.7851 48.9563 64.8144 48.9187L64.9967 48.6616L65.4557 48.0033L65.657 47.6521L66.0656 47.0815L66.4303 46.5674L66.8516 45.9341L67.4299 45.1692C67.4928 45.073 67.5535 44.9873 67.6122 44.9121C67.6918 44.8411 67.7484 44.7763 67.7819 44.7178C67.895 44.5882 68.0438 44.3897 68.2282 44.1221L68.6369 43.5516L68.7499 43.4764L68.6996 43.5642L68.4607 43.9404L68.4167 43.9968C68.3455 44.026 68.2722 44.1201 68.1967 44.279C68.1924 44.2999 68.161 44.348 68.1023 44.4232C68.0646 44.5026 67.987 44.6176 67.8697 44.7681C67.811 44.8433 67.7566 44.8976 67.7063 44.931C67.7063 44.931 67.7042 44.9415 67.7 44.9624C67.7 44.9624 67.7105 44.9645 67.7314 44.9687L67.7628 44.975L67.8697 44.7681L67.8444 44.8936L67.8255 44.9877C67.8004 45.0044 67.7857 45.0232 67.7815 45.0441C67.7982 45.0692 67.8296 45.0755 67.8756 45.063C67.9216 45.0505 67.9383 45.0757 67.9257 45.1384C67.909 45.1133 67.8881 45.1091 67.863 45.1258C67.8378 45.1425 67.8253 45.1508 67.8253 45.1508L67.8127 45.2136L67.8377 45.2513C67.9131 45.2011 67.9424 45.1635 67.9257 45.1384C68.0178 45.1134 68.0618 45.057 68.0577 44.9691C68.0577 44.9691 68.0494 44.9566 68.0327 44.9314C68.0411 44.8896 68.0662 44.8729 68.108 44.8813C68.1207 44.8186 68.1479 44.7914 68.1897 44.7999C68.2106 44.8041 68.2253 44.7853 68.2337 44.7434C68.2003 44.6932 68.215 44.6744 68.2777 44.687L68.284 44.6556C68.2673 44.6305 68.259 44.6179 68.259 44.6179C68.2841 44.6012 68.2988 44.5824 68.303 44.5615L68.4979 44.2417L68.6299 44.0724C68.6551 44.0557 68.7116 43.9909 68.7996 43.8781L68.8436 43.8217L68.9314 43.872L68.9628 43.8783C68.9879 43.8616 68.9921 43.8407 68.9754 43.8156L68.9441 43.8092L68.8436 43.8217L68.938 43.6775L69.007 43.6587L69.0384 43.665C69.0509 43.7111 69.0823 43.7174 69.1325 43.684L69.2582 43.5461C69.2666 43.5042 69.2813 43.4854 69.3022 43.4896L69.3462 43.4332L69.3336 43.496L69.1386 43.8158L69.0946 43.8722C69.0444 43.9056 69.0276 43.9349 69.0443 43.96C69.0192 43.9767 69.0024 44.006 68.994 44.0478C69.0107 44.0729 69.0065 44.0938 68.9813 44.1105L68.975 44.1419C68.975 44.1419 68.9646 44.1398 68.9437 44.1356C68.9437 44.1356 68.9458 44.1251 68.95 44.1042L68.9563 44.0728L68.9626 44.0415L68.9563 44.0728L68.8683 44.1857C68.818 44.2191 68.8222 44.2526 68.8807 44.2861L68.8681 44.3489C68.8094 44.4241 68.7738 44.4931 68.7611 44.5558C68.7611 44.5558 68.7465 44.5746 68.7171 44.6123C68.7129 44.6332 68.7317 44.6478 68.7735 44.6563L68.7546 44.7504C68.7337 44.7462 68.7211 44.7545 68.7169 44.7754L68.7797 44.7881L68.9053 44.6501C68.9849 44.5791 69.0876 44.4475 69.2134 44.2552L69.358 44.0231C69.3622 44.0022 69.3643 43.9918 69.3643 43.9918C69.3852 43.996 69.3957 43.9981 69.3957 43.9981L69.3894 44.0295C69.2762 44.159 69.1945 44.2949 69.1441 44.4371L69.1378 44.4684C69.1587 44.4727 69.1713 44.4643 69.1755 44.4434L69.3641 44.1549C69.3934 44.1173 69.4647 44.0337 69.5778 43.9042C69.582 43.8833 69.5841 43.8728 69.5841 43.8728C69.6092 43.8561 69.6134 43.8352 69.5967 43.8101C69.601 43.7892 69.6135 43.7808 69.6344 43.785C69.6596 43.7683 69.6763 43.7391 69.6847 43.6972L69.7098 43.7349C69.6847 43.7516 69.67 43.7704 69.6658 43.7913C69.6825 43.8165 69.6783 43.8374 69.6532 43.8541C69.628 43.8708 69.6029 43.9419 69.5776 44.0674L69.6466 44.0486L69.785 43.848C69.8352 43.8146 69.8813 43.8021 69.9231 43.8105L69.9921 43.7918L70.0361 43.7353L69.9985 43.7604L69.9294 43.7791C69.9378 43.7373 69.9525 43.7185 69.9734 43.7227C69.9776 43.7018 70.0048 43.6746 70.0551 43.6412L70.0865 43.6475L70.1808 43.5033C70.2017 43.5075 70.2121 43.5096 70.2121 43.5096C70.2164 43.4887 70.2185 43.4783 70.2185 43.4783C70.3021 43.4951 70.3566 43.4408 70.3818 43.3153C70.386 43.2944 70.3986 43.286 70.4195 43.2902C70.4656 43.2777 70.4969 43.2841 70.5136 43.3092C70.5889 43.3679 70.6495 43.3909 70.6955 43.3784L70.7583 43.3911C70.7541 43.412 70.7415 43.4203 70.7206 43.4161L70.4128 43.6479L70.1865 43.9614C70.1656 43.9572 70.153 43.9656 70.1488 43.9865C70.1697 43.9907 70.1823 43.9824 70.1865 43.9614C70.2325 43.949 70.2849 43.9051 70.3435 43.8299L70.4692 43.6919C70.507 43.6125 70.5949 43.554 70.733 43.5166C70.7791 43.5041 70.8314 43.4602 70.8901 43.385L71.0031 43.3098L71.0659 43.3224L71.0469 43.4166L71.0092 43.4416L71.0406 43.4479C71.0824 43.4563 71.1076 43.4396 71.116 43.3978C71.0993 43.3727 71.1014 43.3622 71.1223 43.3664C71.1474 43.3497 71.1704 43.3435 71.1914 43.3477C71.2541 43.3603 71.3169 43.3186 71.3798 43.2224C71.3798 43.2224 71.4803 43.1556 71.6813 43.022L71.675 43.0534L71.5053 43.2477C71.4717 43.3062 71.4591 43.369 71.4674 43.4359C71.5008 43.4862 71.5279 43.5134 71.5489 43.5176C71.6116 43.5302 71.6179 43.5532 71.5676 43.5867L71.4859 43.6681C71.2849 43.8018 71.1069 43.9835 70.9518 44.2134C70.7129 44.5353 70.5158 44.8656 70.3606 45.2043C70.2977 45.3004 70.2327 45.407 70.1657 45.5241C70.1195 45.6453 70.065 45.7541 70.0021 45.8502C69.8637 46.1052 69.6876 46.3853 69.4738 46.6905C69.4025 46.8285 69.2747 47.0312 69.0902 47.2987C69.0567 47.3573 68.9917 47.4639 68.8953 47.6185C68.824 47.7565 68.7339 47.8798 68.625 47.9885L68.562 48.139L68.1218 48.8664L67.8136 49.4246C67.6459 49.7172 67.5327 49.9012 67.474 49.9764C67.4278 50.0977 67.3482 50.2231 67.235 50.3527C67.1051 50.5659 66.9416 50.7832 66.7447 51.0047C66.6608 51.2054 66.5895 51.3434 66.5308 51.4186L66.4868 51.4751L66.2982 51.7635L65.927 52.4722L65.6188 53.0303C65.5852 53.0889 65.5538 53.1369 65.5244 53.1746C65.4993 53.1913 65.4742 53.208 65.4491 53.2247C65.4407 53.2665 65.4239 53.2958 65.3988 53.3125C65.3945 53.3334 65.3631 53.3814 65.3044 53.4567C65.0907 53.7618 64.9293 53.9687 64.8204 54.0774L64.6884 54.2466C64.68 54.2885 64.6653 54.3073 64.6444 54.3031L64.1981 54.8987C64.0096 55.0784 63.8817 55.2811 63.8145 55.5069L63.6322 55.764L63.3366 56.2594C63.2528 56.3514 63.1773 56.4559 63.1103 56.5729C63.0683 56.6733 63.018 56.7611 62.9593 56.8363C62.9048 56.8906 62.8608 57.0015 62.8271 57.1688C62.8102 57.2524 62.8415 57.3131 62.921 57.3509C62.9795 57.3844 63.0046 57.4221 62.9962 57.4639C63.0086 57.51 63.0002 57.5518 62.9709 57.5894L62.8199 57.8528L62.738 58.0975C62.7212 58.1811 62.6793 58.2271 62.6124 58.2354L62.3361 58.3103L62.2671 58.3291C62.2084 58.4043 62.1247 58.4418 62.0159 58.4417C61.928 58.4458 61.8736 58.4457 61.8527 58.4415L61.6142 58.4914C61.5724 58.483 61.5075 58.4808 61.4197 58.4849C61.3276 58.5099 61.2523 58.5056 61.1937 58.472L60.6731 58.3019L60.5038 58.1699C60.1944 57.9771 59.975 57.8241 59.8454 57.711C59.7869 57.6774 59.7409 57.6355 59.7075 57.5853C59.695 57.5392 59.67 57.5015 59.6324 57.4722C59.5196 57.2754 59.4196 57.0159 59.3321 56.6936C59.2529 56.4383 59.1927 56.0889 59.1514 55.6454L59.0457 54.8733L59.059 54.3211C59.0424 54.1872 59.0447 54.0679 59.0657 53.9634C59.0576 53.7876 59.0705 53.5073 59.1044 53.1225C59.1088 52.9928 59.1237 52.8108 59.1491 52.5765C59.1745 52.3423 59.2061 52.131 59.244 51.9428C59.2442 51.834 59.2526 51.7378 59.2695 51.6542C59.3115 51.5538 59.3325 51.4492 59.3326 51.3404L59.4274 50.8699C59.4277 50.6523 59.4383 50.4913 59.4594 50.3867L59.5608 49.5584C59.5945 49.3911 59.6199 49.1569 59.637 48.8556C59.6665 48.7093 59.6898 48.4854 59.7069 48.1842C59.7196 48.1215 59.7092 48.065 59.6758 48.0148L59.5878 48.1276C59.4704 48.2781 59.3929 48.393 59.3551 48.4725C59.3383 48.5561 59.2984 48.646 59.2355 48.7422C59.1769 48.8174 59.1329 48.8738 59.1035 48.9115L58.8709 49.2563C58.7829 49.3692 58.6949 49.482 58.6069 49.5949C58.5189 49.7077 58.4434 49.8122 58.3806 49.9084C58.1626 50.2344 58.0264 50.4246 57.9719 50.4789C57.9384 50.5375 57.8671 50.6211 57.7582 50.7297C57.7456 50.7924 57.7267 50.8322 57.7016 50.8489C57.6932 50.8907 57.6177 50.9952 57.4753 51.1624C57.4668 51.2042 57.3914 51.3087 57.2489 51.4759L56.7083 52.2157L56.2243 52.8364L55.7527 53.5575L55.4634 54.0215C55.3418 54.1929 55.2664 54.2974 55.2371 54.335L55.0924 54.5671C55.038 54.6214 54.9772 54.7071 54.9101 54.8241C54.8723 54.9036 54.8325 54.9935 54.7905 55.0938C54.7528 55.1733 54.7046 55.2506 54.6459 55.3259C54.4697 55.6603 54.3522 55.974 54.2932 56.2668L54.1985 56.7373L54.1164 57.1451C54.0994 57.3376 54.1451 57.597 54.2535 57.9235C54.2493 57.9444 54.2576 57.957 54.2785 57.9612C54.2952 57.9863 54.3015 58.0093 54.2973 58.0302C54.314 58.0554 54.3181 58.0888 54.3097 58.1307C54.2679 58.1223 54.2491 58.1076 54.2533 58.0867C54.2366 58.0615 54.2031 58.0657 54.1529 58.0991C54.0984 58.1534 54.0461 58.1429 53.996 58.0675L53.8644 57.9105ZM52.8119 56.4908C52.791 56.4866 52.7826 56.474 52.7868 56.4531L52.8437 56.1708L52.8624 56.2398L52.8182 56.4594C52.8349 56.4846 52.8433 56.4971 52.8433 56.4971C52.8224 56.4929 52.8119 56.4908 52.8119 56.4908ZM52.9374 56.5161C52.9165 56.5119 52.9081 56.4993 52.9123 56.4784L52.8685 56.3716L52.9188 56.2838L52.9502 56.2902C52.9627 56.3362 52.9605 56.401 52.9437 56.4847L52.9374 56.5161ZM52.9378 56.1897C52.9253 56.1437 52.8939 56.1374 52.8437 56.1708L52.9003 56.0516C52.9045 56.0307 52.9171 56.0224 52.938 56.0266C52.9338 56.0475 52.9317 56.0579 52.9317 56.0579L52.9692 56.196C52.965 56.217 52.9524 56.2253 52.9315 56.2211L52.9378 56.1897ZM52.7506 55.336L52.8576 55.129L52.8639 55.0977L52.8576 55.129C52.8365 55.2336 52.8113 55.3047 52.782 55.3423L52.7506 55.336ZM53.1955 55.8825C53.2164 55.8868 53.229 55.8784 53.2332 55.8575C53.2583 55.8408 53.2772 55.8011 53.2898 55.7383L53.2961 55.707C53.2752 55.7027 53.2626 55.7111 53.2584 55.732C53.2333 55.7487 53.2144 55.7884 53.2018 55.8512L53.1955 55.8825ZM53.9953 53.6933L53.9452 53.618L53.8509 53.7622L53.8822 53.7685L53.9953 53.6933ZM53.5453 52.1991C53.6333 52.0863 53.6899 52.0215 53.715 52.0048L53.7213 51.9734L53.715 52.0048L53.5704 52.2368C53.5495 52.2326 53.5369 52.241 53.5327 52.2619L53.5453 52.1991ZM54.2599 52.8653C54.3646 52.7776 54.4359 52.6396 54.4738 52.4514L54.4424 52.445C54.4131 52.4827 54.3838 52.5203 54.3544 52.5579C54.3293 52.5746 54.3104 52.6143 54.2978 52.6771C54.281 52.7607 54.2579 52.8213 54.2285 52.859L54.2222 52.8903L54.2599 52.8653ZM55.6103 51.9947C55.6312 51.9989 55.6438 51.9905 55.648 51.9696L55.736 51.8568L55.7423 51.8254L55.7109 51.8191C55.7067 51.84 55.6753 51.8881 55.6166 51.9633L55.6103 51.9947ZM56.8047 50.4398L56.7733 50.4335L56.6476 50.5714L56.6413 50.6028L56.6727 50.6091L56.8047 50.4398ZM56.197 49.5667C56.2557 49.4915 56.2871 49.4434 56.2914 49.4225L56.2977 49.3911L56.1657 49.5604L56.197 49.5667ZM56.899 50.2956C56.9199 50.2998 56.9325 50.2914 56.9367 50.2705L56.9744 50.2455C57.1588 49.9779 57.3076 49.7794 57.4207 49.6498C57.4249 49.6289 57.4438 49.5892 57.4773 49.5307C57.5109 49.4722 57.5402 49.4345 57.5653 49.4178L57.8546 48.9538L58.0746 48.6717L58.0809 48.6403C58.06 48.6361 58.0475 48.6444 58.0432 48.6654L57.8736 48.8597L57.8546 48.9538C57.8546 48.9538 57.8295 48.9705 57.7792 49.0039C57.4775 49.4219 57.2616 49.7375 57.1316 49.9507L56.9053 50.2642L56.899 50.2956ZM60.1464 52.9732L60.134 52.8727L60.09 52.9292L60.1024 53.0296L60.1464 52.9732ZM60.518 51.9381L60.4742 51.8314C60.4784 51.8105 60.4701 51.7979 60.4491 51.7937L60.4428 51.8251L60.4489 51.9569C60.4698 51.9611 60.4782 51.9737 60.474 51.9946L60.518 51.9381ZM58.3073 48.3268L58.4079 48.1512L58.4142 48.1198L58.2822 48.2891L58.2759 48.3205L58.3073 48.3268ZM60.443 51.6619L60.487 51.6055L60.4934 51.5741C60.4934 51.5741 60.4829 51.572 60.462 51.5678C60.462 51.5678 60.4599 51.5783 60.4557 51.5992L60.418 51.6242C60.4514 51.6745 60.4681 51.6996 60.4681 51.6996L60.443 51.6619ZM61.053 50.7402L61.0719 50.6461L61.0405 50.6397L61.0092 50.6334L60.9525 50.7526L60.9839 50.7589L61.053 50.7402ZM60.6586 49.9426L60.6839 49.8172L60.6588 49.7795L60.6525 49.8109C60.6274 49.8276 60.6106 49.8568 60.6022 49.8986L60.5959 49.93L60.6272 49.9363L60.6586 49.9426ZM60.4531 48.6935L60.472 48.5994L60.4783 48.568L60.447 48.5617C60.4343 48.6245 60.4155 48.6642 60.3903 48.6809C60.3861 48.7018 60.4049 48.7165 60.4468 48.7249L60.4531 48.6935ZM61.1748 48.6756L61.2125 48.6506L61.2188 48.6192L61.1561 48.6066C61.1561 48.6066 61.1456 48.6044 61.1247 48.6002C61.1247 48.6002 61.1226 48.6107 61.1184 48.6316C61.1351 48.6567 61.1392 48.6902 61.1308 48.732L61.1748 48.6756ZM61.2005 48.2238C61.2047 48.2029 61.2068 48.1924 61.2068 48.1924C61.2277 48.1966 61.2382 48.1987 61.2382 48.1987L61.2822 48.1423C61.2613 48.1381 61.255 48.1151 61.2634 48.0733L61.2321 48.0669L61.2508 48.136C61.2466 48.1569 61.234 48.1653 61.2131 48.161L61.2005 48.2238ZM64.906 50.8957L64.793 50.9708L64.818 51.0085L64.906 50.8957ZM61.1301 44.3579C61.1343 44.3369 61.1364 44.3265 61.1364 44.3265C61.1573 44.3307 61.1678 44.3328 61.1678 44.3328L61.1554 44.2324L61.1114 44.2888L61.1301 44.3579ZM64.938 50.4125C64.9716 50.354 65.0218 50.3206 65.0888 50.3123L65.0637 50.2746L65.0324 50.2683L64.9193 50.3434C64.9193 50.3434 64.9172 50.3539 64.913 50.3748C64.913 50.3748 64.9025 50.3727 64.8816 50.3685L64.938 50.4125ZM65.1326 50.419C65.2162 50.4359 65.256 50.4003 65.252 50.3125L65.2583 50.2811L65.2395 50.2121L65.1955 50.2685C65.2122 50.2936 65.1955 50.3229 65.1452 50.3563L65.1012 50.4127L65.1326 50.419ZM65.3467 49.8419L65.3216 49.8042L65.2086 49.8794L65.2587 49.9548L65.3467 49.8419ZM65.5355 49.3903C65.5564 49.3945 65.569 49.3862 65.5732 49.3653C65.6569 49.3821 65.705 49.3591 65.7176 49.2964C65.7219 49.2755 65.7135 49.2629 65.6926 49.2587L65.6549 49.2838C65.6465 49.3256 65.6235 49.3318 65.5859 49.3025L65.5418 49.3589L65.5355 49.3903ZM66.1448 48.9581L66.1888 48.9016L66.2015 48.8389L66.145 48.7949L66.1387 48.8263C66.1554 48.8514 66.1512 48.8723 66.1261 48.889L66.0821 48.9454L66.1448 48.9581ZM66.1579 48.569L66.3025 48.337L66.2398 48.3243L66.2335 48.3557C66.2544 48.3599 66.2606 48.3829 66.2522 48.4248C66.2019 48.4582 66.1747 48.4853 66.1705 48.5062L66.1516 48.6003L66.1579 48.569ZM66.3524 48.5755C66.3733 48.5797 66.3859 48.5714 66.3901 48.5504L66.4781 48.4376L66.4844 48.4062L66.453 48.3999L66.3337 48.5064L66.3524 48.5755ZM66.4657 48.3372C66.4866 48.3414 66.5222 48.3268 66.5724 48.2934C66.5724 48.2934 66.562 48.2913 66.5411 48.2871C66.5453 48.2661 66.5453 48.2661 66.5411 48.2871C66.4992 48.2786 66.4741 48.2953 66.4657 48.3372ZM66.6478 48.2433L66.6604 48.1805L66.5914 48.1993L66.56 48.1929C66.5558 48.2139 66.5432 48.2222 66.5223 48.218L66.5787 48.262L66.6478 48.2433ZM66.6983 47.9923L66.692 48.0237C66.7338 48.0321 66.7568 48.0258 66.7611 48.0049C66.7653 47.984 66.7507 47.9484 66.7173 47.8982L66.6293 48.011L66.6983 47.9923ZM66.7737 47.9422C66.7779 47.9213 66.78 47.9108 66.78 47.9108C66.8009 47.915 66.8114 47.9171 66.8114 47.9171L66.8177 47.8858C66.8177 47.8858 66.8219 47.8649 66.8303 47.823L66.7676 47.8104L66.7863 47.8794L66.7737 47.9422ZM66.7175 47.735L66.7741 47.6159L66.7804 47.5845L66.7491 47.5782L66.6924 47.6973L66.6861 47.7287L66.7175 47.735ZM66.9057 47.7729C66.9099 47.752 66.9141 47.7311 66.9183 47.7102C66.9477 47.6726 66.9875 47.637 67.0377 47.6036L66.9939 47.4969L66.9625 47.4906L66.9436 47.5847L66.9373 47.6161C66.9121 47.6328 66.8954 47.662 66.887 47.7039C66.8827 47.7248 66.8681 47.7436 66.843 47.7603L66.8366 47.7917L66.9057 47.7729ZM67.1006 47.4531C67.0839 47.428 67.0882 47.4071 67.1133 47.3904C67.1593 47.3779 67.1844 47.3612 67.1887 47.3402L67.2013 47.2775L67.1322 47.2962L67.0819 47.384L67.0065 47.4342L67.1006 47.4531ZM67.3836 47.0204C67.3878 46.9995 67.4004 46.9912 67.4213 46.9954L67.3586 46.9827C67.3586 46.9827 67.3481 46.9806 67.3272 46.9764C67.3272 46.9764 67.3251 46.9869 67.3209 47.0078L67.3396 47.0769L67.3836 47.0204ZM67.5535 46.6629C67.6038 46.6295 67.6331 46.5919 67.6415 46.5501L67.5285 46.6252C67.5242 46.6462 67.5326 46.6587 67.5535 46.6629ZM67.6853 46.6568C67.7271 46.6652 67.7502 46.659 67.7544 46.6381C67.7586 46.6172 67.7502 46.6046 67.7293 46.6004L67.6602 46.6191C67.656 46.6401 67.6539 46.6505 67.6539 46.6505C67.6748 46.6547 67.6853 46.6568 67.6853 46.6568ZM68.0436 46.1741C68.0521 46.1322 68.0688 46.103 68.094 46.0863L68.0626 46.0799L68.0123 46.1677L68.0059 46.1991L68.0436 46.1741ZM68.4841 45.2835C68.4841 45.2835 68.5092 45.2668 68.5594 45.2333L68.7544 44.9135L68.767 44.8508L68.7733 44.8194C68.7482 44.8361 68.7147 44.8403 68.6729 44.8318L68.6352 44.8569C68.6686 44.9071 68.6853 44.9323 68.6853 44.9323C68.6811 44.9532 68.6686 44.9615 68.6476 44.9573C68.6267 44.9531 68.6142 44.9615 68.61 44.9824C68.5889 45.087 68.5533 45.1559 68.503 45.1893L68.4841 45.2835ZM68.6485 44.3047C68.7239 44.2545 68.7615 44.2295 68.7615 44.2295L68.7051 44.1855C68.7009 44.2064 68.6737 44.2336 68.6234 44.267L68.6485 44.3047ZM68.8245 44.079C68.8287 44.058 68.8203 44.0455 68.7994 44.0413L68.7554 44.0977L68.7742 44.1667L68.8245 44.079ZM68.9502 43.941L68.8938 43.897L68.8561 43.9221C68.8561 43.9221 68.854 43.9326 68.8497 43.9535C68.8497 43.9535 68.8602 43.9556 68.8811 43.9598L68.9502 43.941ZM69.8858 43.5092L69.9989 43.434L69.9422 43.5532L69.9045 43.5783L69.8858 43.5092ZM70.3433 43.993C70.3475 43.9721 70.3748 43.9449 70.425 43.9115L70.4 43.8739C70.3581 43.8654 70.333 43.8821 70.3246 43.924L70.3433 43.993ZM69.9989 43.434C70.0115 43.3713 69.9948 43.3462 69.9488 43.3587C69.953 43.3378 69.9802 43.3106 70.0304 43.2772L70.0618 43.2835C70.066 43.2626 70.089 43.2563 70.1309 43.2648C70.1225 43.3066 70.1057 43.3359 70.0806 43.3526C70.0763 43.3735 70.0491 43.4006 69.9989 43.434ZM70.2317 42.926L70.3197 42.8132L70.3448 42.8508L70.2254 42.9574L70.2317 42.926ZM67.82 64.1801L67.7825 64.042C67.7576 63.9499 67.7514 63.8725 67.764 63.8097C67.798 63.4249 67.8318 63.1488 67.8655 62.9815L67.8968 62.9878L67.9728 62.4482L68.1051 62.1157C68.1387 61.9484 68.1723 61.8355 68.2059 61.777C68.2814 61.6181 68.3255 61.5073 68.3381 61.4445L68.3507 61.3818C68.3298 61.3776 68.3194 61.3755 68.3194 61.3755C68.3152 61.3964 68.3131 61.4068 68.3131 61.4068C68.2879 61.4235 68.2712 61.4528 68.2627 61.4946C68.2334 61.5323 68.1684 61.6389 68.0678 61.8145L68.0615 61.8458C68.074 61.8919 68.03 61.9483 67.9295 62.0151L67.8099 62.2848L67.8036 62.3162L67.7785 62.2785L67.8351 62.1593C67.8436 62.1175 67.8373 62.0945 67.8164 62.0903L67.7977 62.0212L67.7537 62.0776L67.697 62.1968C67.6886 62.2386 67.7053 62.2638 67.7471 62.2722L67.7408 62.3035L67.6332 63L67.5956 63.0251L67.6019 62.9937L67.6151 62.4415L67.6469 62.1214C67.6932 61.8914 67.7751 61.7011 67.8924 61.5507L67.9364 61.4942C67.9406 61.4733 67.9532 61.465 67.9741 61.4692L67.9615 61.5319C67.9572 61.5528 67.9216 61.6218 67.8545 61.7389L67.8732 61.8079L67.8983 61.8456L67.9484 61.921C67.9568 61.8792 67.961 61.8582 67.961 61.8582L67.9674 61.8269C67.98 61.7641 68.0031 61.7035 68.0366 61.645C68.0911 61.5907 68.1121 61.5405 68.0996 61.4944C68.1456 61.4819 68.1749 61.4443 68.1876 61.3816C68.2211 61.3231 68.2421 61.2729 68.2505 61.231C68.305 61.1767 68.3553 61.0889 68.4015 60.9677C68.4644 60.8715 68.5126 60.7942 68.5461 60.7356C68.6594 60.4973 68.7579 60.3322 68.8417 60.2402L69.0177 60.0145C69.1435 59.8222 69.2148 59.6843 69.2316 59.6006L69.2506 59.5065C69.2674 59.4228 69.2968 59.3308 69.3388 59.2305C69.4016 59.1343 69.4373 59.0653 69.4457 59.0235C69.4541 58.9817 69.4688 58.9629 69.4897 58.9671C69.519 58.9295 69.5609 58.8835 69.6154 58.8292C69.6699 58.7749 69.7264 58.7101 69.7851 58.6348C69.8396 58.5805 69.8731 58.522 69.8857 58.4593C69.9193 58.4007 69.9528 58.3422 69.9864 58.2837L69.9927 58.2523C69.9633 58.2899 69.9403 58.2962 69.9236 58.271C69.9278 58.2501 69.9195 58.2376 69.8986 58.2333C69.8483 58.2668 69.8211 58.2939 69.8169 58.3148C69.7875 58.3524 69.7582 58.3901 69.7289 58.4277C69.7205 58.4695 69.7016 58.5092 69.6722 58.5468C69.5969 58.597 69.5591 58.6764 69.559 58.7852C69.5506 58.827 69.5254 58.8437 69.4836 58.8353L69.4586 58.7976L69.4712 58.7349C69.5047 58.6763 69.5404 58.6073 69.5781 58.5279C69.6201 58.4275 69.6683 58.3502 69.7228 58.2959C69.8988 58.0702 70.035 57.88 70.1314 57.7253C70.1985 57.6082 70.2635 57.5016 70.3264 57.4055C70.4102 57.3136 70.4835 57.2195 70.5464 57.1234L70.5904 57.0669L70.5967 57.0356L70.5653 57.0293C70.4942 57.0585 70.425 57.1316 70.3579 57.2486C70.3286 57.2863 70.2888 57.3218 70.2386 57.3552C70.2134 57.3719 70.1883 57.3886 70.1632 57.4053C70.0961 57.5223 70.0563 57.6122 70.0436 57.675L69.9619 57.7565C69.9577 57.7774 69.9661 57.7899 69.987 57.7942L69.9807 57.8255L69.7419 58.0386C69.6875 58.0929 69.6183 58.166 69.5345 58.258C69.4717 58.3541 69.4235 58.4315 69.3899 58.49L68.9686 59.1233L68.7234 59.5309L68.673 59.6187L68.3964 60.02C68.3922 60.0409 68.3817 60.0388 68.365 60.0137C68.3441 60.0095 68.3358 59.9969 68.34 59.976L68.3716 59.8192L68.4029 59.8255C68.4363 59.8757 68.4593 59.8695 68.472 59.8067C68.4846 59.744 68.5035 59.7043 68.5286 59.6876C68.5455 59.6039 68.5916 59.4826 68.6671 59.3238L68.6735 59.2924C68.6861 59.2296 68.7469 59.144 68.8558 59.0353L68.9375 58.9538C68.9417 58.9329 68.9563 58.9141 68.9815 58.8974C69.0108 58.8598 69.0359 58.8431 69.0568 58.8473C69.0778 58.8515 69.0924 58.8327 69.1008 58.7909L69.1072 58.7595C69.124 58.6758 69.1869 58.5797 69.2958 58.4711C69.4091 58.2327 69.5537 58.0007 69.7297 57.775C69.8177 57.6622 69.8638 57.5953 69.868 57.5744L70.0316 57.2482C70.0652 57.1897 70.1008 57.1207 70.1386 57.0413C70.1805 56.9409 70.2266 56.874 70.2769 56.8406C70.3104 56.7821 70.3335 56.7214 70.3461 56.6587C70.3839 56.5793 70.4279 56.5228 70.4782 56.4894L70.4908 56.4267C70.449 56.4183 70.4259 56.4245 70.4217 56.4454C70.4008 56.4412 70.3883 56.4496 70.384 56.4705C70.363 56.5751 70.3127 56.6628 70.2331 56.7339C70.1535 56.8049 70.099 56.8592 70.0697 56.8968L69.9754 57.0411C69.9586 57.1247 69.9188 57.1602 69.856 57.1476C69.7933 57.135 69.7535 57.1705 69.7366 57.2541C69.7324 57.275 69.7178 57.2938 69.6926 57.3106C69.6675 57.3273 69.6445 57.3335 69.6236 57.3293L69.5419 57.4108C69.1562 58.0295 68.8335 58.4977 68.5737 58.8153L68.2656 59.2103C68.2614 59.2312 68.2489 59.2395 68.228 59.2353L68.2029 59.1977C68.2113 59.1558 68.2072 59.1223 68.1905 59.0972C68.2576 58.9802 68.3183 58.8945 68.3728 58.8402C68.5112 58.5851 68.5993 58.4179 68.637 58.3384L68.6433 58.3071L68.6056 58.3321L68.4296 58.5578C68.304 58.6413 68.1951 58.75 68.1029 58.8837C68.1029 58.8837 68.0924 58.8816 68.0715 58.8774C68.0715 58.8774 68.0694 58.8879 68.0652 58.9088L68.0715 58.8774L68.0528 58.8084L68.0401 58.8711C67.9564 58.963 67.8516 59.1052 67.7258 59.2975L67.6568 59.3162C67.6777 59.3204 67.6798 59.3099 67.6631 59.2848C67.6631 59.2848 67.6735 59.2869 67.6944 59.2911C67.7615 59.1741 67.8014 59.0842 67.814 59.0214C67.8685 58.9671 67.9335 58.8605 68.009 58.7016L68.0153 58.6703C68.0907 58.6201 68.1493 58.5449 68.1913 58.4445C68.2584 58.3275 68.3066 58.2501 68.3359 58.2125L68.3486 58.1498L68.3612 58.087L68.2921 58.1058C68.2502 58.2061 68.1601 58.3295 68.0218 58.4757C67.9925 58.5133 67.9632 58.5509 67.9338 58.5886C67.9087 58.6053 67.8815 58.6324 67.8521 58.67C67.8019 58.7035 67.7768 58.7202 67.7768 58.7202L67.7957 58.626L67.9717 58.4003C68.0053 58.3418 68.0388 58.2833 68.0723 58.2247C68.1101 58.1453 68.1457 58.0763 68.1793 58.0178L68.3113 57.8485C68.3615 57.8151 68.3679 57.7837 68.3302 57.7544C68.3093 57.7502 68.2989 57.7481 68.2989 57.7481C68.3031 57.7272 68.3052 57.7167 68.3052 57.7167L68.4812 57.491L68.4875 57.4596L68.4561 57.4533L68.3745 57.5348L68.3368 57.5599L68.3494 57.4971C68.3787 57.4595 68.4416 57.3634 68.538 57.2087L69.2107 56.2995L69.7326 55.4906C69.7871 55.4363 69.8353 55.359 69.8772 55.2586C69.9443 55.1416 69.9947 55.0538 70.0282 54.9952C70.2042 54.7695 70.3279 54.5877 70.3992 54.4497C70.462 54.3536 70.5375 54.2491 70.6255 54.1362C70.7386 54.0067 70.8162 53.8917 70.8581 53.7914C71.1515 53.4152 71.361 53.1309 71.4868 52.9387C71.6921 52.6753 71.8619 52.4266 71.9961 52.1925C72.0422 52.0712 72.1093 51.9542 72.1973 51.8413C72.3105 51.7118 72.3838 51.6177 72.4173 51.5592L73.0713 50.581L73.4673 50.0732C73.4966 50.0355 73.5259 49.9979 73.5553 49.9603C73.5888 49.9018 73.6119 49.8411 73.6245 49.7784C73.9179 49.4022 74.1065 49.1138 74.1905 48.9131L74.3728 48.656C74.4063 48.5975 74.4524 48.5306 74.5111 48.4554C74.574 48.3592 74.6264 48.261 74.6684 48.1606L75.2153 47.3894C75.2824 47.2723 75.4563 47.0571 75.737 46.7436C75.8419 46.5471 75.9069 46.4405 75.932 46.4238C75.9865 46.3695 75.9719 46.3339 75.8882 46.3171L75.6372 46.2666C75.2105 46.2242 74.878 46.2007 74.6395 46.1963C74.2964 46.1707 74.0161 46.1578 73.7986 46.1575C73.4807 46.1153 73.0769 46.1211 72.5874 46.1748C72.3238 46.187 72.0894 46.216 71.8844 46.2618C71.6835 46.2866 71.5161 46.3073 71.3822 46.3239L70.2775 46.4606C70.2524 46.4773 70.2273 46.494 70.2022 46.5107C70.0348 46.477 69.8591 46.4851 69.675 46.5351C69.5117 46.5893 69.3841 46.6289 69.292 46.6539C69.0994 46.7457 68.9571 46.8041 68.865 46.829C68.8148 46.8625 68.7896 46.8792 68.7896 46.8792C68.7645 46.8959 68.731 46.9 68.6892 46.8916C68.7101 46.8958 68.7248 46.877 68.7332 46.8352L69.0661 46.641L69.5684 46.4157C69.5935 46.399 69.6291 46.3844 69.6752 46.3719C69.7212 46.3595 69.7463 46.3428 69.7505 46.3218L70.008 46.1778L70.0457 46.1528L70.6485 45.9151L70.7866 45.8776C70.8075 45.8818 70.8431 45.8672 70.8933 45.8338C70.9143 45.838 70.9247 45.8401 70.9247 45.8401C70.9289 45.8192 70.931 45.8087 70.931 45.8087L70.9938 45.8214C71.0356 45.8298 71.0795 45.8277 71.1256 45.8153C71.1758 45.7818 71.224 45.7589 71.27 45.7464L71.2763 45.715L71.2449 45.7087L70.9563 45.6832L70.8999 45.6392L70.9125 45.5765L71.3458 45.37L71.3898 45.3135L71.666 45.2386L71.6723 45.2072L71.641 45.2009L71.5782 45.1883C71.5782 45.1883 71.5761 45.1987 71.5719 45.2196C71.5719 45.2196 71.5614 45.2175 71.5405 45.2133L71.4338 45.2571C71.4338 45.2571 71.4233 45.255 71.4024 45.2508C71.4024 45.2508 71.4045 45.2403 71.4087 45.2194C71.3669 45.211 71.346 45.2068 71.346 45.2068L70.982 45.2314C70.9359 45.2439 70.8815 45.2438 70.8188 45.2312L70.7874 45.2249L70.8314 45.1685L70.9632 45.1624L71.0763 45.0872L71.114 45.0621C71.227 45.0414 71.4007 44.9893 71.6351 44.9059L71.6664 44.9122C71.7501 44.9291 71.8149 44.9313 71.861 44.9188C71.9112 44.8854 72.0451 44.8688 72.2627 44.8691L72.3631 44.8566C72.3924 44.819 72.4176 44.8023 72.4385 44.8065C72.5012 44.8192 72.5661 44.8213 72.633 44.8131C72.7042 44.7839 72.7816 44.7777 72.8652 44.7945L72.8966 44.8008L72.9594 44.8135C72.9845 44.7968 73.0075 44.7905 73.0284 44.7947C73.0702 44.8031 73.1037 44.799 73.1288 44.7823C73.1497 44.7865 73.1979 44.7636 73.2733 44.7135C73.3235 44.68 73.357 44.6759 73.3737 44.701C73.3695 44.7219 73.3674 44.7324 73.3674 44.7324C73.3883 44.7366 73.4009 44.7283 73.4051 44.7073L73.5181 44.6322C73.5223 44.6113 73.514 44.5987 73.4931 44.5945L73.2358 44.5753L72.4199 44.5743C72.399 44.5701 72.3425 44.5805 72.2505 44.6055L72.2191 44.5992L72.2568 44.5741L72.4263 44.5429L72.4703 44.4865C72.4451 44.5032 72.4221 44.5095 72.4012 44.5052L72.3071 44.4863C72.2904 44.4612 72.2611 44.4444 72.2193 44.436L71.6921 44.4604L71.6607 44.4541L71.6984 44.429L72.1001 44.3793L72.4578 44.3861L72.4955 44.361L72.4642 44.3547C72.4432 44.3505 72.4223 44.3463 72.4014 44.3421C72.4056 44.3212 72.3952 44.3191 72.37 44.3358C72.3073 44.3231 72.2529 44.3231 72.2069 44.3356L72.1441 44.3229L72.2132 44.3042C72.4392 44.2626 72.6065 44.2419 72.7153 44.2421L72.7844 44.2233L72.7216 44.2107C72.6171 44.1896 72.5313 44.1833 72.4644 44.1915C72.3974 44.1998 72.3221 44.1955 72.2385 44.1787C72.1548 44.1619 72.0899 44.1597 72.0439 44.1722C71.977 44.1805 71.8807 44.172 71.7553 44.1467L71.7616 44.1153L72.1883 44.1033C72.2135 44.0866 72.2365 44.0804 72.2574 44.0846C72.2992 44.093 72.3327 44.0889 72.3578 44.0722C72.5211 44.018 72.7345 43.9848 72.9981 43.9726C73.3956 43.9438 73.6383 43.9274 73.7261 43.9233C73.747 43.9275 73.7596 43.9191 73.7638 43.8982L73.7011 43.8856C73.6341 43.8939 73.5337 43.9063 73.3998 43.9229C73.291 43.9227 73.1864 43.9017 73.0861 43.8597C73.0694 43.8346 73.0485 43.8304 73.0233 43.8471C73.0233 43.8471 73.0129 43.845 72.992 43.8408L73.0987 43.797L73.2368 43.7595C73.421 43.7095 73.6197 43.6951 73.8331 43.7163C74.0506 43.7166 74.1929 43.7126 74.2598 43.7043L74.6552 43.686L74.7557 43.6736C74.8477 43.6486 74.9251 43.6424 74.9879 43.655C75.2515 43.6428 75.4063 43.6305 75.4523 43.618L75.6155 43.6182L75.7724 43.6498L75.8351 43.6624L75.9355 43.65L75.8477 43.5996L75.4525 43.4548L75.4149 43.4799L75.4525 43.4548L75.8604 43.5369L76.0486 43.5748L76.0863 43.5497C76.1156 43.5121 76.1616 43.4996 76.2244 43.5123C76.3374 43.4915 76.5026 43.4812 76.7202 43.4815L77.2661 43.5261C77.4879 43.5055 77.8163 43.4955 78.2515 43.496C78.3854 43.4795 78.6238 43.4839 78.9669 43.5095C79.0799 43.4887 79.2221 43.4847 79.3936 43.4975C79.5694 43.4893 79.7012 43.4832 79.789 43.4791C80.1614 43.4671 80.4856 43.4779 80.7617 43.5118C80.8914 43.5161 81.0107 43.5184 81.1194 43.5185C81.2533 43.5019 81.3851 43.4958 81.5148 43.5002C81.6194 43.5212 81.7365 43.5339 81.8662 43.5383C82.0001 43.5217 82.1298 43.526 82.2553 43.5513L82.6568 43.6648C82.7362 43.7025 82.8304 43.7215 82.9391 43.7216L83.1147 43.8223L83.259 43.9166L83.3217 43.9292C83.3927 44.0088 83.4889 44.0717 83.6101 44.1178C83.7314 44.164 83.813 44.1913 83.8548 44.1997C83.8966 44.2082 84.0053 44.2627 84.1809 44.3633C84.3565 44.464 84.484 44.5875 84.5633 44.7341C84.605 44.8513 84.7386 45.0523 84.9641 45.3371C85.0394 45.3957 85.102 45.4627 85.1522 45.5381C85.2023 45.6135 85.2545 45.6784 85.3088 45.7329C85.3046 45.7538 85.3192 45.7894 85.3526 45.8396C85.4027 45.915 85.4193 45.9945 85.4025 46.0782L85.3772 46.2036C85.3646 46.2664 85.329 46.281 85.2705 46.2474C85.2538 46.2223 85.2182 46.2369 85.1638 46.2912C85.1135 46.3246 85.0842 46.3622 85.0757 46.4041C85.0673 46.4459 85.0485 46.4856 85.0191 46.5232C85.0107 46.5651 85.0127 46.609 85.0252 46.655C85.0627 46.7932 85.0751 46.8936 85.0625 46.9563C85.0457 47.04 85.0435 47.1048 85.056 47.1509C85.0518 47.1718 85.0621 47.2827 85.0869 47.4835C85.0743 47.5463 85.0157 47.5671 84.9111 47.546L84.5098 47.2694C84.4471 47.2568 84.3927 47.2567 84.3467 47.2692C84.2839 47.2566 84.2547 47.2398 84.2589 47.2189C84.0458 46.9801 83.8494 46.8209 83.6696 46.7412C83.5943 46.6825 83.4417 46.63 83.2116 46.5837C82.9858 46.5165 82.7202 46.4848 82.4147 46.4886C82.1135 46.4714 81.8981 46.4607 81.7684 46.4564L80.6889 46.4675L80.099 46.4793L80.0049 46.4604L80.055 46.5358L80.1112 46.7429C80.1446 46.7932 80.1613 46.8183 80.1613 46.8183C80.2783 46.9942 80.278 47.1573 80.1607 47.3078L80.1858 47.3455C80.194 47.4124 80.1731 47.4626 80.1228 47.496C80.0768 47.5085 80.0412 47.5231 80.0161 47.5398C80.0119 47.5607 79.9993 47.5691 79.9784 47.5649C79.9575 47.5607 79.947 47.5586 79.947 47.5586L79.7527 47.3889L79.6586 47.3699C79.6377 47.3657 79.623 47.3845 79.6146 47.4264C79.5601 47.4807 79.4555 47.514 79.3007 47.5264C79.2797 47.5222 79.2316 47.5451 79.1562 47.5952C79.1269 47.6328 78.9991 47.7812 78.7728 48.0403C78.5928 48.1781 78.3958 48.3996 78.1821 48.7048L77.4968 49.6766L76.8431 50.4917L76.3151 51.1688C76.1851 51.382 76.0593 51.5743 75.9378 51.7456C75.8204 51.8961 75.7157 52.0382 75.6235 52.172C75.3343 52.5273 75.1709 52.7446 75.1331 52.8241C75.1038 52.8617 75.0723 52.9097 75.0388 52.9683C75.0053 53.0268 74.9717 53.0853 74.9382 53.1439L74.6805 53.451C74.5589 53.6224 74.4814 53.7374 74.4478 53.7959L74.1712 54.1972L73.7625 54.7678L73.2472 55.3821C73.1256 55.5535 73.0083 55.704 72.8951 55.8336C72.8029 55.9673 72.7128 56.0906 72.6248 56.2035L71.9397 57.0122C71.7762 57.2839 71.6107 57.5117 71.4431 57.6956C71.2 58.0384 71.0281 58.2975 70.9275 58.4731C70.8939 58.5317 70.8562 58.6111 70.8142 58.7115C70.7765 58.7909 70.7136 58.8871 70.6256 58.9999C70.5627 59.0961 70.4873 59.2006 70.3993 59.3134C70.307 59.4472 70.2148 59.5809 70.1226 59.7147L69.2426 60.8432L68.9847 61.3136L68.6514 61.834C68.4166 62.2437 68.2802 62.5427 68.2423 62.7309L68.0152 63.6971L67.9769 64.2117C67.9727 64.2326 67.9601 64.2409 67.9392 64.2367L67.9455 64.2053C67.9455 64.2053 67.9476 64.1949 67.9518 64.174C67.9518 64.174 67.9393 64.1823 67.9141 64.199L67.9204 64.1677C67.8995 64.1635 67.887 64.1718 67.8828 64.1927L67.8388 64.2491L67.82 64.1801ZM68.2764 60.6161C68.3937 60.4656 68.4713 60.3506 68.509 60.2712L68.5781 60.2524C68.5236 60.3068 68.4335 60.4301 68.3078 60.6224L68.2638 60.6788L68.2764 60.6161ZM68.5781 60.2524C68.5907 60.1897 68.5887 60.1458 68.572 60.1207L68.616 60.0642L68.6347 60.1333L68.5781 60.2524ZM70.043 58.1645L70.1624 58.058L70.1436 57.9889C70.1394 58.0098 70.1269 58.0182 70.1059 58.014L70.0116 58.1582L70.0053 58.1896L70.043 58.1645ZM69.7259 45.9578C69.7677 45.9662 69.7929 45.9495 69.8013 45.9077C69.864 45.9203 69.9079 45.9183 69.9331 45.9016L69.9644 45.9079L70.2219 45.7639C70.2973 45.7138 70.4082 45.7035 70.5546 45.7329L70.611 45.7769L70.5483 45.7643L70.3725 45.8268C70.3389 45.8854 70.2908 45.9083 70.228 45.8957C70.1862 45.8873 70.1276 45.9081 70.0522 45.9582L69.82 45.9768C69.7949 45.9935 69.7719 45.9997 69.751 45.9955C69.7552 45.9746 69.7468 45.962 69.7259 45.9578ZM71.1761 45.5643C71.2263 45.5309 71.2619 45.5163 71.2828 45.5205L71.2578 45.4828L71.151 45.5266L71.1761 45.5643ZM71.6668 44.5859L71.6982 44.5922L71.9618 44.58L71.9932 44.5863L71.9555 44.6114C71.8885 44.6196 71.8028 44.6133 71.6982 44.5922L71.6668 44.5859ZM87.839 64.7503C87.8056 64.7 87.7304 64.6414 87.6133 64.5743C87.584 64.6119 87.5526 64.6056 87.5192 64.5553C87.3812 64.484 87.3102 64.4045 87.3061 64.3166L87.2499 64.1094L87.2124 63.9713L87.225 63.9086C87.2335 63.8667 87.2293 63.8333 87.2126 63.8081L87.1813 63.8018C87.1855 63.7809 87.1751 63.7244 87.1501 63.6323C87.1543 63.6114 87.1502 63.578 87.1377 63.5319C87.1419 63.511 87.1608 63.4713 87.1943 63.4127C87.2194 63.396 87.2216 63.3312 87.2008 63.2182C87.1883 63.1722 87.157 63.1659 87.1067 63.1993L87.1004 63.2306C87.0795 63.2264 87.0711 63.2139 87.0753 63.1929C87.1006 63.0675 87.1091 62.9712 87.1008 62.9043C87.105 62.8834 87.0904 62.8478 87.057 62.7976L87.0696 62.7348L87.0947 62.7725L87.1261 62.7788C87.1387 62.7161 87.1346 62.6826 87.1136 62.6784C87.0927 62.6742 87.0844 62.6616 87.0886 62.6407C87.1012 62.578 87.1201 62.5382 87.1452 62.5215C87.1494 62.5006 87.1557 62.4692 87.1642 62.4274L87.1705 62.396L87.1328 62.4211L87.1202 62.4838L87.0888 62.4775C87.0721 62.4524 87.0701 62.4085 87.0827 62.3457C87.0702 62.2997 87.0765 62.2683 87.1016 62.2516C87.1058 62.2307 87.1101 62.2098 87.1143 62.1889L87.1456 62.1952C87.1959 62.1618 87.2231 62.1346 87.2273 62.1137C87.2315 62.0928 87.2169 62.0572 87.1835 62.007C87.171 61.9609 87.1732 61.8961 87.1901 61.8124C87.2069 61.7288 87.2468 61.6389 87.3096 61.5427C87.3516 61.4424 87.3768 61.3713 87.3852 61.3294C87.4146 61.2918 87.446 61.2438 87.4795 61.1852C87.5131 61.1267 87.5571 61.0703 87.6115 61.016C87.6786 60.8989 87.7143 60.8299 87.7185 60.809L87.7248 60.7776C87.7248 60.7776 87.7143 60.7755 87.6934 60.7713C87.6934 60.7713 87.6913 60.7818 87.6871 60.8027L87.5488 61.0033C87.4901 61.0786 87.4566 61.1371 87.4482 61.1789L87.3791 61.1977L87.3917 61.1349C87.4002 61.0931 87.4337 61.0346 87.4924 60.9593C87.505 60.8966 87.5407 60.8276 87.5993 60.7524C87.6371 60.6729 87.6727 60.6039 87.7063 60.5454C87.7398 60.4869 87.7734 60.4283 87.8069 60.3698L87.9579 60.1064C87.9788 60.1106 87.9788 60.1106 87.9579 60.1064C87.9621 60.0855 87.9642 60.075 87.9642 60.075L87.9768 60.0123C87.9852 59.9705 88.0188 59.9119 88.0774 59.8367L88.0838 59.8053L88.0524 59.799L88.0084 59.8554L87.9707 59.8805L87.977 59.8491C87.977 59.8491 87.9666 59.847 87.9456 59.8428C87.9456 59.8428 87.9478 59.8324 87.952 59.8114L87.9456 59.8428L87.8136 60.0121L87.776 60.0371L87.7823 60.0058C87.7991 59.9221 87.8222 59.8615 87.8515 59.8239C87.8642 59.7611 87.883 59.7214 87.9082 59.7047C87.9375 59.6671 87.9668 59.6295 87.9962 59.5919L88.0341 59.4036L88.0027 59.3973C87.9818 59.3931 87.9692 59.4015 87.965 59.4224L87.8959 59.4411C87.8959 59.4411 87.8855 59.439 87.8646 59.4348C87.8688 59.4139 87.8814 59.4055 87.9023 59.4097C87.9191 59.3261 87.9505 59.278 87.9966 59.2655L88.0029 59.2341C88.0407 59.1547 88.091 59.0669 88.1539 58.9708C88.2167 58.8746 88.2628 58.8077 88.2922 58.7701C88.3508 58.6949 88.3844 58.6363 88.3928 58.5945C88.4179 58.5778 88.42 58.5674 88.3991 58.5631C88.4033 58.5422 88.4075 58.5213 88.4118 58.5004C88.3699 58.492 88.3469 58.4982 88.3427 58.5191C88.3427 58.5191 88.3176 58.5358 88.2673 58.5693L88.2863 58.4751L88.3743 58.3623L88.3806 58.3309L88.3492 58.3246C88.3408 58.3664 88.3115 58.404 88.2612 58.4375L88.2549 58.4688C88.2591 58.4479 88.2508 58.4354 88.2298 58.4311L88.2865 58.312L88.2928 58.2806C88.2719 58.2764 88.2593 58.2847 88.2551 58.3057C88.2049 58.3391 88.1734 58.3871 88.1608 58.4499C88.1399 58.4457 88.1273 58.454 88.1231 58.4749L88.1858 58.4876C88.1858 58.4876 88.1837 58.498 88.1795 58.5189C88.1795 58.5189 88.19 58.521 88.2109 58.5253C88.19 58.521 88.1774 58.5294 88.1732 58.5503C88.1147 58.5168 88.077 58.5418 88.0602 58.6255L87.7271 58.9828L87.7334 58.9514L87.878 58.7194C87.9996 58.548 88.1107 58.3745 88.2113 58.1989L88.488 57.7976L88.532 57.7412C88.4901 57.7328 88.4671 57.739 88.4629 57.7599L88.3309 57.9292L88.2869 57.9856C88.2953 57.9438 88.31 57.925 88.3309 57.9292L88.7459 57.3273C88.8883 57.1601 89.0853 56.8842 89.3368 56.4996L89.6512 56.0733C89.7434 55.9395 89.8481 55.7974 89.9655 55.6469C90.087 55.4755 90.2002 55.2916 90.3051 55.0951C90.3513 54.9738 90.4037 54.8756 90.4623 54.8003C90.521 54.7251 90.5671 54.6582 90.6007 54.5997C90.7851 54.3322 90.913 54.1294 90.9843 53.9914L91.4245 53.264L91.7578 52.7435C91.8919 52.5094 91.9821 52.3317 92.0283 52.2105L92.154 52.0725C92.3426 51.7841 92.4915 51.5312 92.6005 51.3138C92.6383 51.2343 92.7158 51.1194 92.8332 50.9689L93.2925 49.9842L93.6069 49.5578L93.7578 49.2944L93.8898 49.1252L93.9652 49.0751C93.9778 49.0123 94.0177 48.9224 94.0848 48.8053L94.3298 48.5609C94.355 48.5442 94.3717 48.5149 94.3802 48.4731C94.4304 48.4397 94.466 48.4251 94.4869 48.4293C94.5496 48.4419 94.6271 48.4358 94.7191 48.4108L94.7254 48.3794C94.759 48.3209 94.7863 48.2393 94.8073 48.1348C94.82 48.072 94.8828 48.0303 94.9958 48.0095C95.0376 48.0179 95.0711 48.0138 95.0962 47.9971C95.1213 47.9804 95.1464 47.9637 95.1716 47.947C95.1758 47.926 95.203 47.8989 95.2533 47.8655C95.2575 47.8446 95.27 47.8362 95.2909 47.8404L95.3099 47.7463L95.3789 47.7276L95.3413 47.7526L95.36 47.8217C95.3809 47.8259 95.3914 47.828 95.3914 47.828C95.3956 47.8071 95.3977 47.7966 95.3977 47.7966C95.4395 47.805 95.4583 47.8197 95.4541 47.8406L95.4855 47.8469L95.5169 47.8533L95.5105 47.8846L95.3848 48.0225L95.3659 48.1166L95.4099 48.0602C95.4141 48.0393 95.4727 48.0185 95.5857 47.9977C95.6066 48.0019 95.6484 48.0103 95.7112 48.023C95.7991 48.0189 95.8702 47.9897 95.9247 47.9354L95.9624 47.9103L95.9811 47.9794C95.9727 48.0212 95.9768 48.0547 95.9935 48.0798C96.0438 48.0464 96.0689 48.0297 96.0689 48.0297C96.094 48.013 96.1883 47.9231 96.3516 47.7602C96.4437 47.7352 96.5044 47.7039 96.5338 47.6663C96.5338 47.6663 96.5442 47.6684 96.5651 47.6726C96.586 47.6768 96.5944 47.6894 96.5902 47.7103C96.5985 47.7772 96.6486 47.7982 96.7407 47.7732C96.7449 47.7523 96.7575 47.744 96.7784 47.7482L96.7344 47.8046C96.7302 47.8255 96.7155 47.8443 96.6904 47.861C96.6653 47.8777 96.6611 47.8986 96.6778 47.9238C96.6945 47.9489 96.7342 47.9678 96.7969 47.9804C96.8806 47.9972 96.9204 47.9617 96.9163 47.8739C96.9247 47.832 96.9499 47.8153 96.9917 47.8238C97.0544 47.8364 97.1109 47.826 97.1612 47.7926C97.2072 47.7801 97.2616 47.7802 97.3243 47.7928C97.3871 47.8054 97.4373 47.8264 97.4749 47.8557C97.4749 47.8557 97.4916 47.8809 97.525 47.9311C97.5375 47.9772 97.5165 48.0273 97.462 48.0817C97.4327 48.1193 97.4159 48.1485 97.4117 48.1695C97.4033 48.2113 97.4095 48.2343 97.4305 48.2385L97.4241 48.2699L97.2797 48.3387L97.2671 48.4015C97.3548 48.5062 97.3755 48.6736 97.3292 48.9036L97.2787 49.1546C97.245 49.3219 97.1569 49.5435 97.0143 49.8195C96.9639 49.9616 96.9092 50.1791 96.8503 50.4719L96.8124 50.6602C96.7618 50.9111 96.7385 51.1893 96.7423 51.4947C96.7546 51.6496 96.748 51.8985 96.7225 52.2415C96.7266 52.3294 96.7097 52.413 96.672 52.4925C96.6551 52.5761 96.6487 52.6619 96.6528 52.7498C96.6318 52.8543 96.6211 53.0154 96.6208 53.233C96.5828 53.53 96.5614 53.9065 96.5566 54.3625L96.5116 55.2348L96.4731 55.9125C96.456 56.2137 96.4306 56.448 96.3969 56.6153C96.3713 56.9583 96.3417 57.2135 96.308 57.3808C96.3038 57.4017 96.3122 57.4143 96.3331 57.4185C96.3078 57.544 96.2951 57.7155 96.2948 57.9331L96.3259 58.1025C96.3551 58.1737 96.3633 58.3494 96.3504 58.6297C96.342 58.6716 96.3293 58.7343 96.3125 58.818C96.3208 58.8849 96.2977 58.9455 96.2432 58.9999L96.262 59.0689L96.331 59.0502L96.5637 58.7053L96.878 58.279L97.1357 57.9718L97.3117 57.7461L97.6008 57.4452L97.8208 57.1631L97.9654 56.9311C97.9947 56.8934 98.0702 56.7889 98.1917 56.6176L98.6004 56.047C98.6339 55.9885 98.6654 55.9404 98.6947 55.9028C98.7282 55.8442 98.7597 55.7962 98.789 55.7586L98.9713 55.5015L99.4303 54.8431L99.6316 54.4919L100.04 53.9214L100.405 53.4072L100.826 52.7739L101.404 52.009C101.467 51.9128 101.528 51.8272 101.587 51.7519C101.666 51.6809 101.723 51.6161 101.756 51.5576C101.87 51.428 102.018 51.2295 102.203 50.962L102.611 50.3914L102.725 50.3162L102.674 50.404L102.435 50.7803L102.391 50.8367C102.32 50.8659 102.247 50.9599 102.171 51.1188C102.167 51.1397 102.136 51.1878 102.077 51.263C102.039 51.3425 101.962 51.4574 101.844 51.6079C101.786 51.6831 101.731 51.7375 101.681 51.7709C101.681 51.7709 101.679 51.7813 101.675 51.8022C101.675 51.8022 101.685 51.8043 101.706 51.8086L101.737 51.8149L101.844 51.6079L101.819 51.7334L101.8 51.8275C101.775 51.8442 101.76 51.863 101.756 51.8839C101.773 51.9091 101.804 51.9154 101.85 51.9029C101.896 51.8904 101.913 51.9155 101.9 51.9782C101.884 51.9531 101.863 51.9489 101.838 51.9656C101.812 51.9823 101.8 51.9907 101.8 51.9907L101.787 52.0534L101.812 52.0911C101.888 52.041 101.917 52.0034 101.9 51.9782C101.992 51.9533 102.036 51.8968 102.032 51.809C102.032 51.809 102.024 51.7964 102.007 51.7713C102.016 51.7295 102.041 51.7128 102.083 51.7212C102.095 51.6584 102.122 51.6313 102.164 51.6397C102.185 51.6439 102.2 51.6251 102.208 51.5833C102.175 51.533 102.19 51.5142 102.252 51.5268L102.259 51.4955C102.242 51.4703 102.234 51.4578 102.234 51.4578C102.259 51.4411 102.273 51.4223 102.278 51.4014L102.473 51.0815L102.605 50.9123C102.63 50.8956 102.686 50.8308 102.774 50.7179L102.818 50.6615L102.906 50.7118L102.937 50.7181C102.963 50.7014 102.967 50.6805 102.95 50.6554L102.919 50.6491L102.818 50.6615L102.913 50.5173L102.982 50.4986L103.013 50.5049C103.025 50.5509 103.057 50.5572 103.107 50.5238L103.233 50.3859C103.241 50.3441 103.256 50.3253 103.277 50.3295L103.321 50.2731L103.308 50.3358L103.113 50.6556L103.069 50.712C103.019 50.7454 103.002 50.7747 103.019 50.7998C102.994 50.8165 102.977 50.8458 102.969 50.8876C102.985 50.9128 102.981 50.9337 102.956 50.9504L102.95 50.9817C102.95 50.9817 102.939 50.9796 102.918 50.9754C102.918 50.9754 102.92 50.965 102.925 50.9441L102.931 50.9127L102.937 50.8813L102.931 50.9127L102.843 51.0255C102.793 51.0589 102.797 51.0924 102.855 51.126L102.843 51.1887C102.784 51.2639 102.748 51.3329 102.736 51.3957C102.736 51.3957 102.721 51.4145 102.692 51.4521C102.687 51.473 102.706 51.4877 102.748 51.4961L102.729 51.5902C102.708 51.586 102.696 51.5943 102.691 51.6153L102.754 51.6279L102.88 51.49C102.96 51.419 103.062 51.2873 103.188 51.095L103.333 50.863C103.337 50.8421 103.339 50.8316 103.339 50.8316C103.36 50.8358 103.37 50.8379 103.37 50.8379L103.364 50.8693C103.251 50.9989 103.169 51.1347 103.119 51.2769L103.112 51.3083C103.133 51.3125 103.146 51.3041 103.15 51.2832L103.339 50.9948C103.368 50.9572 103.439 50.8736 103.552 50.744C103.557 50.7231 103.559 50.7127 103.559 50.7127C103.584 50.696 103.588 50.675 103.571 50.6499C103.576 50.629 103.588 50.6207 103.609 50.6249C103.634 50.6082 103.651 50.5789 103.659 50.5371L103.684 50.5748C103.659 50.5915 103.645 50.6103 103.64 50.6312C103.657 50.6563 103.653 50.6772 103.628 50.6939C103.603 50.7106 103.577 50.7817 103.552 50.9072L103.621 50.8885L103.76 50.6878C103.81 50.6544 103.856 50.6419 103.898 50.6503L103.967 50.6316L104.011 50.5752L103.973 50.6002L103.904 50.619C103.912 50.5771 103.927 50.5583 103.948 50.5625C103.952 50.5416 103.979 50.5145 104.03 50.4811L104.061 50.4874L104.155 50.3432C104.176 50.3474 104.187 50.3495 104.187 50.3495C104.191 50.3286 104.193 50.3181 104.193 50.3181C104.277 50.3349 104.331 50.2806 104.356 50.1551C104.361 50.1342 104.373 50.1259 104.394 50.1301C104.44 50.1176 104.472 50.1239 104.488 50.149C104.563 50.2077 104.624 50.2308 104.67 50.2183L104.733 50.2309C104.729 50.2518 104.716 50.2602 104.695 50.256L104.387 50.4878L104.161 50.8013C104.14 50.7971 104.128 50.8054 104.123 50.8263C104.144 50.8306 104.157 50.8222 104.161 50.8013C104.207 50.7888 104.259 50.7449 104.318 50.6697L104.444 50.5318C104.482 50.4523 104.569 50.3939 104.708 50.3564C104.754 50.3439 104.806 50.3 104.865 50.2248L104.978 50.1496L105.04 50.1623L105.022 50.2564L104.984 50.2814L105.015 50.2878C105.057 50.2962 105.082 50.2795 105.091 50.2377C105.074 50.2125 105.076 50.2021 105.097 50.2063C105.122 50.1896 105.145 50.1833 105.166 50.1875C105.229 50.2002 105.291 50.1584 105.354 50.0623C105.354 50.0623 105.455 49.9955 105.656 49.8618L105.65 49.8932L105.48 50.0875C105.446 50.1461 105.434 50.2088 105.442 50.2758C105.475 50.326 105.503 50.3532 105.523 50.3574C105.586 50.3701 105.592 50.3931 105.542 50.4265L105.46 50.508C105.26 50.6416 105.081 50.8234 104.926 51.0533C104.687 51.3751 104.49 51.7054 104.335 52.0441C104.272 52.1402 104.207 52.2469 104.14 52.3639C104.094 52.4852 104.04 52.5939 103.977 52.69C103.838 52.9451 103.662 53.2252 103.448 53.5303C103.377 53.6683 103.249 53.871 103.065 54.1386C103.031 54.1971 102.966 54.3037 102.87 54.4584C102.799 54.5964 102.708 54.7197 102.6 54.8283L102.537 54.9789L102.096 55.7063L101.788 56.2644C101.62 56.5571 101.507 56.741 101.449 56.8163C101.402 56.9375 101.323 57.0629 101.21 57.1925C101.08 57.4057 100.916 57.6231 100.719 57.8445C100.635 58.0453 100.564 58.1832 100.505 58.2585L100.461 58.3149L100.273 58.6033L99.9016 59.312L99.5933 59.8702C99.5598 59.9287 99.5284 59.9768 99.499 60.0144C99.4739 60.0311 99.4488 60.0478 99.4237 60.0645C99.4152 60.1063 99.3985 60.1356 99.3733 60.1523C99.3691 60.1732 99.3377 60.2213 99.279 60.2965C99.0653 60.6017 98.9039 60.8086 98.795 60.9172L98.663 61.0865C98.6546 61.1283 98.6399 61.1471 98.619 61.1429L98.1727 61.7385C97.9842 61.9182 97.8563 62.1209 97.7891 62.3468L97.6067 62.6039L97.3112 63.0993C97.2274 63.1912 97.1519 63.2957 97.0848 63.4128C97.0429 63.5131 96.9926 63.6009 96.9339 63.6762C96.8794 63.7305 96.8354 63.8413 96.8017 64.0086C96.7848 64.0923 96.8161 64.153 96.8956 64.1907C96.9541 64.2243 96.9792 64.2619 96.9707 64.3038C96.9832 64.3498 96.9748 64.3916 96.9455 64.4293L96.7945 64.6926L96.7126 64.9373C96.6958 65.0209 96.6539 65.0669 96.5869 65.0752L96.3107 65.1502L96.2417 65.1689C96.183 65.2441 96.0993 65.2817 95.9905 65.2815C95.9026 65.2856 95.8482 65.2855 95.8273 65.2813L95.5888 65.3312C95.5469 65.3228 95.4821 65.3206 95.3942 65.3247C95.3022 65.3497 95.2269 65.3454 95.1683 65.3119L94.6477 65.1418L94.4784 65.0098C94.169 64.8169 93.9496 64.6639 93.82 64.5508C93.7615 64.5173 93.7155 64.4754 93.6821 64.4251C93.6696 64.3791 93.6446 64.3414 93.6069 64.3121C93.4942 64.1153 93.3941 63.8557 93.3067 63.5335C93.2275 63.2782 93.1673 62.9287 93.126 62.4852L93.0203 61.7132L93.0336 61.1609C93.017 61.027 93.0193 60.9078 93.0403 60.8032C93.0322 60.6275 93.0451 60.3472 93.079 59.9623C93.0834 59.8326 93.0983 59.6506 93.1237 59.4164C93.1491 59.1821 93.1807 58.9709 93.2186 58.7826C93.2187 58.6739 93.2272 58.5777 93.2441 58.494C93.286 58.3936 93.3071 58.2891 93.3072 58.1803L93.402 57.7097C93.4022 57.4922 93.4129 57.3311 93.434 57.2265L93.5354 56.3983C93.5691 56.231 93.5945 55.9967 93.6116 55.6955C93.6411 55.5491 93.6644 55.3253 93.6815 55.0241C93.6941 54.9613 93.6837 54.9048 93.6503 54.8546L93.5623 54.9674C93.445 55.1179 93.3675 55.2329 93.3297 55.3123C93.3129 55.396 93.273 55.4859 93.2101 55.582C93.1514 55.6573 93.1074 55.7137 93.0781 55.7513L92.8455 56.0962C92.7575 56.209 92.6695 56.3219 92.5815 56.4347C92.4935 56.5476 92.418 56.6521 92.3551 56.7482C92.1372 57.0743 92.0009 57.2645 91.9465 57.3188C91.9129 57.3773 91.8417 57.4609 91.7328 57.5695C91.7202 57.6323 91.7013 57.672 91.6762 57.6887C91.6677 57.7305 91.5923 57.835 91.4498 58.0022C91.4414 58.044 91.366 58.1485 91.2235 58.3157L90.6829 59.0556L90.1988 59.6762L89.7272 60.3973L89.438 60.8614C89.3164 61.0328 89.241 61.1373 89.2116 61.1749L89.067 61.4069C89.0126 61.4612 88.9518 61.5469 88.8847 61.664C88.8469 61.7434 88.8071 61.8333 88.7651 61.9337C88.7274 62.0131 88.6791 62.0905 88.6205 62.1657C88.4443 62.5002 88.3268 62.8138 88.2678 63.1066L88.1731 63.5772L88.091 63.985C88.074 64.1774 88.1197 64.4369 88.2281 64.7633C88.2239 64.7843 88.2322 64.7968 88.2531 64.801C88.2698 64.8262 88.2761 64.8492 88.2719 64.8701C88.2886 64.8952 88.2927 64.9287 88.2843 64.9705C88.2425 64.9621 88.2237 64.9474 88.2279 64.9265C88.2112 64.9014 88.1777 64.9055 88.1274 64.9389C88.073 64.9933 88.0207 64.9827 87.9706 64.9074L87.839 64.7503ZM86.7865 63.3306C86.7656 63.3264 86.7572 63.3139 86.7614 63.293L86.8183 63.0106L86.837 63.0797L86.7928 63.2993C86.8095 63.3244 86.8178 63.337 86.8178 63.337C86.7969 63.3327 86.7865 63.3306 86.7865 63.3306ZM86.912 63.3559C86.891 63.3517 86.8827 63.3391 86.8869 63.3182L86.8431 63.2115L86.8934 63.1237L86.9248 63.13C86.9373 63.176 86.9351 63.2409 86.9183 63.3245L86.912 63.3559ZM86.9124 63.0296C86.8999 62.9835 86.8685 62.9772 86.8183 63.0106L86.8749 62.8915C86.8791 62.8705 86.8917 62.8622 86.9126 62.8664C86.9084 62.8873 86.9063 62.8978 86.9063 62.8978L86.9437 63.0359C86.9395 63.0568 86.927 63.0652 86.9061 63.0609L86.9124 63.0296ZM86.7252 62.1758L86.8321 61.9689L86.8385 61.9375L86.8321 61.9689C86.8111 62.0734 86.7859 62.1445 86.7566 62.1821L86.7252 62.1758ZM87.1701 62.7224C87.191 62.7266 87.2035 62.7182 87.2078 62.6973C87.2329 62.6806 87.2518 62.6409 87.2644 62.5782L87.2707 62.5468C87.2498 62.5426 87.2372 62.5509 87.233 62.5718C87.2079 62.5886 87.189 62.6283 87.1764 62.691L87.1701 62.7224ZM87.9699 60.5332L87.9198 60.4578L87.8254 60.602L87.8568 60.6083L87.9699 60.5332ZM87.5199 59.039C87.6079 58.9261 87.6645 58.8614 87.6896 58.8447L87.6959 58.8133L87.6896 58.8447L87.545 59.0767C87.5241 59.0725 87.5115 59.0808 87.5073 59.1017L87.5199 59.039ZM88.2345 59.7051C88.3392 59.6174 88.4105 59.4794 88.4484 59.2912L88.417 59.2849C88.3877 59.3225 88.3584 59.3601 88.329 59.3977C88.3039 59.4144 88.285 59.4542 88.2724 59.5169C88.2556 59.6005 88.2325 59.6612 88.2031 59.6988L88.1968 59.7302L88.2345 59.7051ZM89.5849 58.8345C89.6058 58.8387 89.6184 58.8304 89.6226 58.8095L89.7106 58.6966L89.7169 58.6652L89.6855 58.6589C89.6813 58.6798 89.6499 58.7279 89.5912 58.8031L89.5849 58.8345ZM90.7793 57.2796L90.7479 57.2733L90.6222 57.4112L90.6159 57.4426L90.6472 57.4489L90.7793 57.2796ZM90.1716 56.4066C90.2303 56.3313 90.2617 56.2832 90.2659 56.2623L90.2723 56.231L90.1402 56.4002L90.1716 56.4066ZM90.8736 57.1354C90.8945 57.1396 90.907 57.1313 90.9113 57.1104L90.9489 57.0853C91.1334 56.8178 91.2822 56.6192 91.3953 56.4897C91.3995 56.4688 91.4184 56.4291 91.4519 56.3705C91.4855 56.312 91.5148 56.2744 91.5399 56.2577L91.8292 55.7936L92.0492 55.5115L92.0555 55.4801C92.0346 55.4759 92.022 55.4843 92.0178 55.5052L91.8481 55.6995L91.8292 55.7936C91.8292 55.7936 91.8041 55.8103 91.7538 55.8437C91.452 56.2617 91.2362 56.5773 91.1062 56.7906L90.8799 57.1041L90.8736 57.1354ZM94.121 59.813L94.1086 59.7126L94.0646 59.769L94.077 59.8694L94.121 59.813ZM94.4926 58.778L94.4488 58.6712C94.453 58.6503 94.4446 58.6378 94.4237 58.6336L94.4174 58.6649L94.4235 58.7967C94.4444 58.8009 94.4528 58.8135 94.4486 58.8344L94.4926 58.778ZM92.2818 55.1666L92.3825 54.991L92.3888 54.9597L92.2568 55.129L92.2505 55.1603L92.2818 55.1666ZM94.4176 58.5018L94.4616 58.4453L94.4679 58.414C94.4679 58.414 94.4575 58.4119 94.4366 58.4077C94.4366 58.4077 94.4345 58.4181 94.4303 58.439L94.3926 58.4641C94.426 58.5143 94.4427 58.5394 94.4427 58.5394L94.4176 58.5018ZM95.0275 57.58L95.0465 57.4859L95.0151 57.4796L94.9837 57.4733L94.9271 57.5924L94.9585 57.5987L95.0275 57.58ZM94.6332 56.7825L94.6584 56.657L94.6334 56.6193L94.6271 56.6507C94.6019 56.6674 94.5852 56.6967 94.5768 56.7385L94.5704 56.7699L94.6018 56.7762L94.6332 56.7825ZM94.4277 55.5334L94.4466 55.4392L94.4529 55.4079L94.4216 55.4016C94.4089 55.4643 94.3901 55.504 94.3649 55.5207C94.3607 55.5416 94.3795 55.5563 94.4214 55.5647L94.4277 55.5334ZM95.1494 55.5154L95.1871 55.4904L95.1934 55.459L95.1307 55.4464C95.1307 55.4464 95.1202 55.4443 95.0993 55.4401C95.0993 55.4401 95.0972 55.4505 95.093 55.4714C95.1097 55.4966 95.1138 55.53 95.1054 55.5719L95.1494 55.5154ZM95.1751 55.0636C95.1793 55.0427 95.1814 55.0323 95.1814 55.0323C95.2023 55.0365 95.2128 55.0386 95.2128 55.0386L95.2568 54.9821C95.2359 54.9779 95.2296 54.9549 95.238 54.9131L95.2067 54.9068L95.2254 54.9758C95.2212 54.9967 95.2086 55.0051 95.1877 55.0009L95.1751 55.0636ZM98.8806 57.7355L98.7676 57.8107L98.7926 57.8484L98.8806 57.7355ZM95.1047 51.1977C95.1089 51.1768 95.111 51.1663 95.111 51.1663C95.1319 51.1705 95.1424 51.1726 95.1424 51.1726L95.1299 51.0722L95.0859 51.1286L95.1047 51.1977ZM98.9126 57.2523C98.9462 57.1938 98.9964 57.1604 99.0634 57.1521L99.0383 57.1144L99.0069 57.1081L98.8939 57.1833C98.8939 57.1833 98.8918 57.1937 98.8876 57.2146C98.8876 57.2146 98.8771 57.2125 98.8562 57.2083L98.9126 57.2523ZM99.1072 57.2589C99.1908 57.2757 99.2306 57.2402 99.2265 57.1523L99.2329 57.1209L99.2141 57.0519L99.1701 57.1083C99.1868 57.1334 99.17 57.1627 99.1198 57.1961L99.0758 57.2525L99.1072 57.2589ZM99.3213 56.6818L99.2962 56.6441L99.1832 56.7192L99.2333 56.7946L99.3213 56.6818ZM99.5101 56.2301C99.531 56.2344 99.5436 56.226 99.5478 56.2051C99.6315 56.2219 99.6796 56.199 99.6922 56.1362C99.6964 56.1153 99.6881 56.1028 99.6672 56.0986L99.6295 56.1236C99.6211 56.1654 99.5981 56.1717 99.5604 56.1424L99.5164 56.1988L99.5101 56.2301ZM100.119 55.7979L100.163 55.7415L100.176 55.6787L100.12 55.6347L100.113 55.6661C100.13 55.6912 100.126 55.7121 100.101 55.7288L100.057 55.7853L100.119 55.7979ZM100.132 55.4088L100.277 55.1768L100.214 55.1642L100.208 55.1955C100.229 55.1998 100.235 55.2228 100.227 55.2646C100.177 55.298 100.149 55.3252 100.145 55.3461L100.126 55.4402L100.132 55.4088ZM100.327 55.4153C100.348 55.4196 100.36 55.4112 100.365 55.3903L100.453 55.2774L100.459 55.2461L100.428 55.2398L100.308 55.3463L100.327 55.4153ZM100.44 55.177C100.461 55.1812 100.497 55.1666 100.547 55.1332C100.547 55.1332 100.537 55.1311 100.516 55.1269C100.52 55.106 100.52 55.106 100.516 55.1269C100.474 55.1185 100.449 55.1352 100.44 55.177ZM100.622 55.0831L100.635 55.0204L100.566 55.0391L100.535 55.0328C100.53 55.0537 100.518 55.0621 100.497 55.0578L100.553 55.1018L100.622 55.0831ZM100.673 54.8321L100.667 54.8635C100.708 54.8719 100.731 54.8657 100.736 54.8448C100.74 54.8239 100.725 54.7883 100.692 54.738L100.604 54.8509L100.673 54.8321ZM100.748 54.782C100.752 54.7611 100.755 54.7507 100.755 54.7507C100.776 54.7549 100.786 54.757 100.786 54.757L100.792 54.7256C100.792 54.7256 100.796 54.7047 100.805 54.6629L100.742 54.6502L100.761 54.7193L100.748 54.782ZM100.692 54.5749L100.749 54.4557L100.755 54.4243L100.724 54.418L100.667 54.5372L100.661 54.5685L100.692 54.5749ZM100.88 54.6128C100.884 54.5918 100.889 54.5709 100.893 54.55C100.922 54.5124 100.962 54.4769 101.012 54.4435L100.968 54.3367L100.937 54.3304L100.918 54.4245L100.912 54.4559C100.887 54.4726 100.87 54.5019 100.862 54.5437C100.857 54.5646 100.843 54.5834 100.818 54.6001L100.811 54.6315L100.88 54.6128ZM101.075 54.2929C101.059 54.2678 101.063 54.2469 101.088 54.2302C101.134 54.2177 101.159 54.201 101.163 54.1801L101.176 54.1173L101.107 54.1361L101.056 54.2239L100.981 54.274L101.075 54.2929ZM101.358 53.8603C101.362 53.8394 101.375 53.831 101.396 53.8352L101.333 53.8226C101.333 53.8226 101.323 53.8205 101.302 53.8163C101.302 53.8163 101.3 53.8267 101.295 53.8476L101.314 53.9167L101.358 53.8603ZM101.528 53.5028C101.578 53.4694 101.608 53.4318 101.616 53.3899L101.503 53.4651C101.499 53.486 101.507 53.4986 101.528 53.5028ZM101.66 53.4967C101.702 53.5051 101.725 53.4988 101.729 53.4779C101.733 53.457 101.725 53.4445 101.704 53.4402L101.635 53.459C101.631 53.4799 101.629 53.4904 101.629 53.4904C101.649 53.4946 101.66 53.4967 101.66 53.4967ZM102.018 53.0139C102.027 52.9721 102.043 52.9428 102.069 52.9261L102.037 52.9198L101.987 53.0076L101.981 53.0389L102.018 53.0139ZM102.459 52.1233C102.459 52.1233 102.484 52.1066 102.534 52.0732L102.729 51.7534L102.742 51.6906L102.748 51.6593C102.723 51.676 102.689 51.6801 102.647 51.6717L102.61 51.6967C102.643 51.747 102.66 51.7721 102.66 51.7721C102.656 51.793 102.643 51.8014 102.622 51.7972C102.601 51.793 102.589 51.8013 102.585 51.8222C102.563 51.9268 102.528 51.9958 102.478 52.0292L102.459 52.1233ZM102.623 51.1445C102.698 51.0944 102.736 51.0693 102.736 51.0693L102.68 51.0253C102.675 51.0462 102.648 51.0734 102.598 51.1068L102.623 51.1445ZM102.799 50.9188C102.803 50.8979 102.795 50.8853 102.774 50.8811L102.73 50.9375L102.749 51.0066L102.799 50.9188ZM102.925 50.7809L102.868 50.7369L102.831 50.7619C102.831 50.7619 102.829 50.7724 102.824 50.7933C102.824 50.7933 102.835 50.7954 102.856 50.7996L102.925 50.7809ZM103.86 50.3491L103.973 50.2739L103.917 50.3931L103.879 50.4181L103.86 50.3491ZM104.318 50.8329C104.322 50.8119 104.349 50.7848 104.4 50.7514L104.375 50.7137C104.333 50.7053 104.308 50.722 104.299 50.7638L104.318 50.8329ZM103.973 50.2739C103.986 50.2111 103.969 50.186 103.923 50.1985C103.928 50.1776 103.955 50.1504 104.005 50.117L104.036 50.1233C104.041 50.1024 104.064 50.0962 104.105 50.1046C104.097 50.1464 104.08 50.1757 104.055 50.1924C104.051 50.2133 104.024 50.2405 103.973 50.2739ZM104.206 49.7658L104.294 49.653L104.319 49.6907L104.2 49.7972L104.206 49.7658ZM100.82 67.5921L100.808 67.3285C100.825 67.2449 100.814 67.1884 100.777 67.1591L100.789 67.0963L100.852 66.7826C100.919 66.6656 100.959 66.5757 100.972 66.5129C100.98 66.4711 100.957 66.4229 100.903 66.3685C100.882 66.3643 100.863 66.3496 100.847 66.3245C100.851 66.3036 100.855 66.2827 100.859 66.2617L100.872 66.199C100.885 66.1363 100.918 66.0777 100.973 66.0234C101.023 65.99 101.063 65.9545 101.092 65.9169C101.125 65.8583 101.245 65.6974 101.45 65.4341C101.568 65.2836 101.647 65.1582 101.689 65.0579L101.721 65.0642L101.79 65.0454C101.798 65.0036 101.832 64.9451 101.89 64.8698L102.23 64.318L102.236 64.2866C102.286 64.2532 102.314 64.2261 102.318 64.2052C102.347 64.1675 102.364 64.1383 102.368 64.1174L102.563 63.7975L102.676 63.5592L102.683 63.5278C102.683 63.5278 102.672 63.5257 102.651 63.5215C102.651 63.5215 102.649 63.532 102.645 63.5529L102.469 63.7786C102.469 63.7786 102.459 63.7765 102.438 63.7723C102.438 63.7723 102.436 63.7827 102.431 63.8037L102.438 63.7723L102.45 63.7095L102.413 63.7346L102.381 63.7283L102.388 63.6969L102.564 63.4712L102.79 63.1577C102.849 63.0825 102.88 63.0344 102.884 63.0135L103.148 62.6749L103.136 62.5745L103.06 62.6246L102.979 62.7061L102.998 62.612L103.004 62.5806L102.998 62.612C102.859 62.7582 102.776 62.8502 102.746 62.8878C102.696 62.9212 102.629 62.9839 102.545 63.0758C102.466 63.1468 102.407 63.2221 102.369 63.3015L102.294 63.3516L102.306 63.2889C102.403 63.1342 102.464 63.0485 102.489 63.0318C102.577 62.919 102.642 62.8124 102.684 62.712C102.747 62.6159 102.807 62.5302 102.866 62.4549C102.925 62.3797 102.958 62.3212 102.967 62.2793L102.973 62.248L102.967 62.2793L102.935 62.273L102.891 62.3294L102.904 62.2667L102.917 62.204L102.923 62.1726C102.902 62.1684 102.889 62.1767 102.885 62.1976C102.864 62.1934 102.852 62.2018 102.848 62.2227L102.86 62.16L102.923 62.0094C102.927 61.9885 102.919 61.9759 102.898 61.9717C102.898 61.9717 102.888 61.9696 102.867 61.9654C102.867 61.9654 102.865 61.9759 102.86 61.9968C102.806 62.0511 102.745 62.1368 102.678 62.2539L102.42 62.5611L102.024 63.0689L101.188 64.141C101.109 64.212 101.05 64.2872 101.012 64.3667C100.979 64.4252 100.947 64.4733 100.918 64.5109C100.868 64.5443 100.838 64.5819 100.83 64.6237L100.516 65.0501C100.491 65.0668 100.474 65.0961 100.465 65.1379L100.434 65.1316C100.434 65.1316 100.424 65.1295 100.403 65.1253C100.407 65.1043 100.419 65.096 100.44 65.1002C100.608 64.8075 100.721 64.6236 100.78 64.5484L101.459 63.6079L102.182 62.611L102.201 62.5168L102.157 62.5733L102.075 62.6547L101.685 63.1312C101.652 63.1897 101.532 63.3507 101.327 63.614L101.333 63.5826L101.472 63.382L101.528 63.2628L101.535 63.2314C101.493 63.223 101.482 63.2209 101.503 63.2251C101.528 63.2084 101.543 63.1896 101.547 63.1687L101.598 62.9177L101.359 63.1308C101.338 63.1266 101.323 63.1454 101.315 63.1872C101.298 63.1621 101.294 63.1286 101.303 63.0868C101.311 63.045 101.345 62.9864 101.403 62.9112L101.686 62.4785C101.716 62.4409 101.739 62.3803 101.755 62.2966L101.887 62.1273L101.894 62.096L101.862 62.0897L101.649 62.3404L101.58 62.3592C101.584 62.3382 101.565 62.3236 101.523 62.3152C101.507 62.29 101.511 62.2691 101.536 62.2524L101.8 61.9139L102.435 61.0298L102.655 60.7477L102.668 60.6849L102.598 60.7037L102.46 60.9043C102.456 60.9252 102.443 60.9336 102.422 60.9294L102.429 60.898L102.441 60.8353L102.41 60.8289C102.351 60.9042 102.297 60.9585 102.247 60.9919L102.253 60.9605L102.435 60.7035C102.465 60.6658 102.528 60.5697 102.624 60.415L102.995 59.8695L103.554 59.0355C103.73 58.8098 103.852 58.6385 103.919 58.5214L104.46 57.7815L104.938 57.0291L105.522 56.2328L106.321 55.0226L106.755 54.3265L107.654 52.9407C107.88 52.5729 108.079 52.2865 108.251 52.0817C108.306 52.0274 108.45 51.8498 108.685 51.5488L108.936 51.273L109.2 50.9345C109.293 50.8007 109.414 50.7381 109.565 50.7467C109.586 50.7509 109.619 50.7467 109.665 50.7342C109.715 50.7008 109.761 50.6883 109.803 50.6968C109.916 50.676 109.991 50.6803 110.029 50.7096C110.05 50.7138 110.079 50.7306 110.117 50.7599C110.159 50.7683 110.213 50.7684 110.28 50.7601C110.33 50.7267 110.37 50.7456 110.399 50.8168C110.458 50.8503 110.52 50.8629 110.587 50.8547L110.813 50.8675C110.897 50.8843 110.96 50.9514 111.001 51.0686L111.058 51.1126C111.104 51.2088 111.168 51.2654 111.252 51.2823C111.361 51.2824 111.436 51.2867 111.478 51.2951C111.658 51.3748 111.781 51.4649 111.848 51.5654C111.99 51.7246 112.107 51.9005 112.199 52.093C112.299 52.2438 112.349 52.3191 112.349 52.3191C112.366 52.3443 112.42 52.3987 112.512 52.4825C112.545 52.5328 112.562 52.5579 112.562 52.5579L112.681 52.7777C112.765 52.9033 112.741 52.9639 112.612 52.9596C112.524 52.9637 112.438 53.0117 112.354 53.1036C112.296 53.1788 112.227 53.1976 112.147 53.1598C112.043 53.1388 111.974 53.1575 111.94 53.216C111.936 53.237 111.913 53.2432 111.871 53.2348L111.752 53.1782C111.689 53.1655 111.649 53.1466 111.633 53.1215C111.553 53.0838 111.486 53.092 111.432 53.1464C111.206 53.2967 111.017 53.4764 110.866 53.6854C110.782 53.7773 110.682 53.8985 110.565 54.049C110.451 54.1785 110.332 54.3395 110.206 54.5317L109.578 55.3844L109.106 56.1056L108.691 56.7075C108.666 56.7242 108.622 56.7806 108.559 56.8768C108.517 56.9771 108.448 57.0503 108.352 57.0962C108.326 57.1129 108.308 57.1526 108.295 57.2153C108.211 57.3073 108.157 57.3616 108.132 57.3783C108.081 57.4117 107.998 57.5036 107.88 57.6541L107.478 58.1933L107.12 58.6761L106.711 59.2466L106.353 59.7294C106.181 59.9342 105.944 60.2456 105.642 60.6636L105.07 61.3971L104.63 61.9614L104.266 62.4755C104.228 62.555 104.175 62.6532 104.108 62.7703C104.041 62.8874 103.949 63.0211 103.832 63.1716C103.794 63.251 103.733 63.3367 103.649 63.4287C103.591 63.5039 103.528 63.6 103.461 63.7171L102.914 64.4883L102.7 64.7391L102.637 64.8896L102.492 65.1216L102.367 65.2595L102.36 65.2909C102.285 65.341 102.203 65.4225 102.115 65.5354C102.027 65.6482 101.956 65.7318 101.902 65.7861L101.682 66.0682C101.514 66.2521 101.397 66.457 101.329 66.6828L101.348 66.7519C101.407 66.7854 101.411 66.8189 101.361 66.8523C101.277 66.9442 101.224 67.0425 101.203 67.1471C101.161 67.2474 101.073 67.3603 100.939 67.4856C100.927 67.5484 100.908 67.5881 100.883 67.6048L100.839 67.6612L100.82 67.5921ZM100.772 65.8851L100.778 65.8537L100.822 65.7973L100.841 65.8663L100.835 65.8977L100.753 65.9792L100.772 65.8851ZM101.192 66.2308L101.217 66.1053L101.23 66.0426L101.242 65.9798L101.198 66.0362C101.169 66.0739 101.146 66.1345 101.129 66.2182L101.148 66.2872L101.192 66.2308ZM101.255 66.2434C101.25 66.2643 101.259 66.2769 101.28 66.2811C101.301 66.2853 101.313 66.277 101.317 66.256C101.359 66.2645 101.384 66.2478 101.393 66.2059C101.397 66.185 101.387 66.1285 101.362 66.0365L101.274 66.1493L101.236 66.1744C101.228 66.2162 101.234 66.2392 101.255 66.2434ZM101.061 65.7474C101.128 65.6303 101.193 65.5237 101.256 65.4276L101.293 65.4025C101.289 65.4234 101.287 65.4339 101.287 65.4339C101.304 65.459 101.3 65.4799 101.274 65.4966C101.249 65.5133 101.233 65.5426 101.224 65.5844C101.212 65.6472 101.191 65.6973 101.161 65.735C101.153 65.7768 101.119 65.8353 101.061 65.9106L101.029 65.9042L101.061 65.7474ZM101.537 66.1371C101.558 66.1413 101.571 66.1329 101.575 66.112L101.676 65.9364C101.684 65.8946 101.699 65.8758 101.72 65.88L101.694 65.8423L101.613 65.9238L101.606 65.9552C101.594 66.0179 101.573 66.0681 101.544 66.1057L101.537 66.1371ZM100.992 65.4398C101.001 65.398 101.022 65.3478 101.055 65.2893C101.114 65.214 101.158 65.1576 101.187 65.12L101.47 64.6873C101.499 64.6497 101.522 64.5891 101.539 64.5054L101.577 64.4803L101.571 64.5117C101.566 64.5326 101.564 64.5431 101.564 64.5431C101.585 64.5473 101.596 64.5494 101.596 64.5494C101.638 64.5578 101.644 64.5808 101.614 64.6185L101.394 64.9006C101.374 64.8964 101.361 64.9047 101.357 64.9256L101.376 64.9947C101.38 64.9738 101.392 64.9654 101.413 64.9696L101.426 64.9069C101.447 64.9111 101.455 64.9237 101.451 64.9446C101.442 64.9864 101.426 65.0157 101.401 65.0324L101.231 65.2267L101.218 65.2895C101.218 65.2895 101.216 65.2999 101.212 65.3208C101.208 65.3417 101.218 65.3439 101.243 65.3271L101.237 65.3585L101.055 65.4524C101.051 65.4733 101.038 65.4817 101.017 65.4775L100.979 65.5025L100.992 65.4398ZM101.74 64.6437L101.595 64.8757L101.564 64.8694L101.74 64.6437ZM101.99 65.5101C102.011 65.5143 102.023 65.506 102.028 65.485L102.248 65.2029L102.216 65.1966L101.965 65.4724C101.986 65.4766 101.994 65.4892 101.99 65.5101ZM101.696 64.8633C101.7 64.8424 101.692 64.8298 101.671 64.8256L101.891 64.5435C101.912 64.5477 101.924 64.5394 101.928 64.5184L101.922 64.5498L101.702 64.8319L101.696 64.8633ZM101.885 64.4117L101.891 64.3803C101.887 64.4013 101.885 64.4117 101.885 64.4117C101.906 64.4159 101.916 64.418 101.916 64.418L101.74 64.6437L101.885 64.4117ZM101.904 63.9913C101.912 63.9494 101.929 63.9202 101.954 63.9035L102.067 63.8283L102.061 63.8597L102.017 63.9161L101.935 63.9976L101.929 64.0289L101.904 63.9913ZM101.985 64.2361C102.01 64.2194 102.027 64.1901 102.036 64.1483L102.168 63.979L102.243 63.9289L102.224 64.023L102.01 64.2738L101.979 64.2675L101.985 64.2361ZM102.124 63.546C102.128 63.525 102.156 63.4979 102.206 63.4645C102.21 63.4436 102.223 63.4352 102.244 63.4394L102.237 63.4708L102.156 63.5523C102.151 63.5732 102.139 63.5815 102.118 63.5773L102.124 63.546ZM102.72 63.5028C102.725 63.4819 102.727 63.4714 102.727 63.4714C102.748 63.4756 102.758 63.4777 102.758 63.4777L102.896 63.2771L102.903 63.2457C102.903 63.2457 102.892 63.2436 102.871 63.2394C102.871 63.2394 102.869 63.2499 102.865 63.2708L102.739 63.4087L102.72 63.5028ZM102.546 62.5863C102.571 62.5696 102.586 62.5508 102.59 62.5299C102.598 62.4881 102.615 62.4588 102.64 62.4421L102.678 62.417L102.665 62.4798L102.577 62.5926C102.577 62.5926 102.567 62.5905 102.546 62.5863C102.546 62.5863 102.544 62.5968 102.54 62.6177L102.546 62.5863ZM103.243 62.5307C103.268 62.514 103.287 62.4743 103.299 62.4115C103.249 62.445 103.222 62.4721 103.217 62.493L103.211 62.5244L103.243 62.5307ZM104.844 61.8738L105.001 61.7422L104.994 61.7736L104.875 61.8801C104.871 61.901 104.858 61.9094 104.837 61.9052L104.844 61.8738ZM111.297 68.4936C111.192 68.4726 111.107 68.4118 111.04 68.3113L110.921 68.2547C110.774 68.2252 110.659 68.1476 110.576 68.022C110.496 67.9843 110.432 67.9277 110.381 67.8523C110.31 67.7728 110.212 67.7203 110.087 67.6951C110.062 67.7118 110.02 67.7034 109.961 67.6698C109.903 67.6363 109.852 67.6153 109.811 67.6069L109.441 67.3365C109.332 67.1188 109.192 66.9492 109.021 66.8277C108.908 66.7397 108.82 66.6893 108.757 66.6767C108.653 66.6557 108.592 66.5782 108.576 66.4443C108.547 66.3731 108.436 66.2747 108.244 66.1489C108.089 66.0525 107.936 65.8368 107.786 65.5019C107.757 65.4308 107.697 65.1901 107.605 64.78C107.589 64.6461 107.601 64.5289 107.643 64.4286L107.612 64.4223L107.775 64.0961C107.851 63.9373 107.895 63.8264 107.908 63.7637L108.021 63.5254C108.071 63.492 108.115 63.4355 108.153 63.3561C108.191 63.2766 108.212 63.2265 108.216 63.2055C108.166 63.1302 108.155 63.0737 108.185 63.0361C108.239 62.9817 108.269 62.9441 108.273 62.9232C108.323 62.781 108.401 62.6661 108.505 62.5783C108.602 62.4237 108.705 62.2376 108.814 62.0202C108.856 61.9198 108.95 61.7756 109.097 61.5875C109.155 61.5123 109.333 61.2761 109.631 60.8791C109.736 60.6825 109.832 60.5279 109.92 60.415C110.012 60.2813 110.09 60.1663 110.153 60.0702C110.291 59.9239 110.425 59.7442 110.555 59.531C110.681 59.4474 110.76 59.322 110.794 59.1547L110.851 59.0355L110.989 58.8349C111.01 58.8391 111.033 58.8329 111.058 58.8162C111.083 58.7995 111.098 58.7806 111.102 58.7597L111.184 58.6783C111.418 58.3773 111.555 58.1871 111.592 58.1077C111.706 57.9781 111.806 57.8569 111.894 57.7441C111.986 57.6103 112.062 57.5058 112.12 57.4306L112.473 56.9792C112.506 56.9206 112.571 56.814 112.667 56.6594C112.764 56.5047 112.867 56.373 112.975 56.2644C113.118 56.0972 113.212 55.953 113.258 55.8317L113.548 55.3677C113.627 55.2967 113.684 55.2319 113.717 55.1733C113.755 55.0939 113.789 55.0354 113.818 54.9978C113.831 54.935 113.881 54.8472 113.969 54.7344C114.015 54.7219 114.032 54.6926 114.019 54.6466C114.032 54.5838 114.03 54.5399 114.013 54.5148L113.85 54.3514C113.854 54.3305 113.848 54.3075 113.831 54.2823C113.84 54.2405 113.857 54.2112 113.882 54.1945C113.903 54.09 113.897 54.0126 113.863 53.9623L113.876 53.8996L113.901 53.7741C113.889 53.6193 113.947 53.544 114.077 53.5484C114.127 53.515 114.209 53.4879 114.322 53.4671C114.594 53.4131 114.831 53.3192 115.032 53.1856C115.073 53.194 115.101 53.1669 115.113 53.1041L115.509 52.4331C115.539 52.3955 115.547 52.3537 115.535 52.3076C115.543 52.2658 115.564 52.2156 115.598 52.1571C115.627 52.1195 115.673 52.0526 115.736 51.9565C115.824 51.8436 115.914 51.7747 116.006 51.7497C116.182 51.6328 116.385 51.5975 116.615 51.6438C116.824 51.6859 116.979 51.7279 117.079 51.7699C117.18 51.8119 117.272 51.8957 117.355 52.0213C117.414 52.0548 117.47 52.0988 117.524 52.1533C117.579 52.2077 117.635 52.2517 117.694 52.2853C117.706 52.3313 117.75 52.3837 117.825 52.4423C117.921 52.5052 117.988 52.5513 118.026 52.5807L118.264 52.8571C118.297 52.9074 118.345 52.9388 118.408 52.9514C118.63 52.9308 118.812 52.8913 118.954 52.8329C119.436 52.7122 119.888 52.6291 120.31 52.5836C120.637 52.4752 120.955 52.4087 121.264 52.384C121.557 52.3341 121.787 52.3261 121.955 52.3597L122.174 52.4039L122.457 52.4608C122.478 52.465 122.528 52.486 122.607 52.5237C122.691 52.5406 122.747 52.5846 122.776 52.6557C122.793 52.6809 122.822 52.6976 122.864 52.7061C122.906 52.7145 122.946 52.7334 122.983 52.7627C123 52.7878 123.029 52.8046 123.071 52.813C123.092 52.8172 123.1 52.8298 123.096 52.8507L123.065 52.8444C123.044 52.8402 123.021 52.8464 122.996 52.8631C122.992 52.884 122.99 52.8945 122.99 52.8945L123.008 52.9635L122.971 52.9886L122.983 53.089L123.196 53.1646C123.196 53.1646 123.213 53.1897 123.246 53.24C123.263 53.2651 123.278 53.3007 123.29 53.3467C123.307 53.3718 123.319 53.4179 123.328 53.4848C123.315 53.5476 123.328 53.5936 123.365 53.623C123.403 53.6523 123.43 53.6795 123.447 53.7046C123.468 53.7088 123.488 53.7674 123.509 53.8804C123.547 53.9098 123.574 53.937 123.591 53.9621C123.628 53.9915 123.655 54.0187 123.672 54.0438C123.739 54.1443 123.741 54.2426 123.678 54.3388C123.653 54.4643 123.623 54.5563 123.59 54.6148L123.583 54.8093C123.587 54.8972 123.571 54.9809 123.533 55.0603L123.363 55.4178L123.225 55.6185L123.162 55.6058C123.128 55.5556 123.141 55.4928 123.2 55.4176C123.225 55.4009 123.242 55.3716 123.25 55.3298C123.263 55.2671 123.261 55.2231 123.244 55.198C123.231 55.152 123.219 55.1059 123.206 55.0599C123.194 55.0139 123.146 54.9824 123.062 54.9656C123.041 54.9614 123.027 54.9802 123.018 55.022L122.974 55.0784L122.987 55.0157C122.97 54.9906 122.968 54.9466 122.981 54.8839L122.792 54.846L122.698 54.827C122.64 54.7935 122.556 54.7767 122.447 54.7765C122.129 54.8431 121.893 54.8825 121.738 54.8949C121.466 54.9489 121.06 55.0195 120.52 55.1067C120.077 55.148 119.753 55.1915 119.547 55.2372C119.434 55.258 119.265 55.2892 119.039 55.3307C118.817 55.3514 118.631 55.3574 118.48 55.3488C118.413 55.3571 118.334 55.3738 118.242 55.3987C118.175 55.407 118.095 55.4237 118.003 55.4486C117.869 55.4652 117.803 55.4735 117.803 55.4735C117.669 55.4901 117.56 55.4899 117.476 55.4731C117.451 55.4898 117.405 55.5023 117.338 55.5106C117.275 55.4979 117.242 55.5021 117.238 55.523L117.143 55.6672L116.766 56.2441C116.707 56.3193 116.621 56.4217 116.508 56.5513C116.42 56.6641 116.343 56.7791 116.276 56.8961C116.129 57.0842 116.022 57.2368 115.955 57.3539C115.867 57.4667 115.769 57.5775 115.66 57.6861C115.572 57.799 115.482 57.9223 115.389 58.056L115.264 58.1939L115.257 58.2253L115.32 58.2379L115.728 58.1569C115.858 58.1612 115.973 58.1844 116.073 58.2263C116.111 58.2557 116.234 58.2914 116.443 58.3335C116.506 58.3461 116.542 58.3859 116.55 58.4529C116.567 58.478 116.596 58.4948 116.638 58.5032C116.813 58.6038 116.922 58.6583 116.964 58.6668L116.951 58.7295L116.92 58.7232C116.899 58.719 116.886 58.7273 116.882 58.7483C116.878 58.7692 116.865 58.7775 116.844 58.7733C116.865 58.7775 116.874 58.7901 116.869 58.811C116.865 58.8319 116.874 58.8445 116.895 58.8487L117.108 58.9243L117.139 58.9306L117.246 59.0499L117.108 59.0874C117.024 59.0706 116.97 59.0705 116.944 59.0872L116.913 59.0809C116.909 59.1018 116.917 59.1144 116.938 59.1186L117.026 59.1689L117.34 59.2321C117.381 59.2405 117.44 59.274 117.515 59.3327C117.536 59.4457 117.576 59.519 117.634 59.5525L117.816 59.6218C117.875 59.6553 117.9 59.693 117.891 59.7348C117.887 59.7557 117.874 59.7641 117.854 59.7599L117.615 59.6466L117.552 59.634C117.573 59.6382 117.582 59.6508 117.578 59.6717C117.586 59.7386 117.617 59.7993 117.671 59.8538C117.751 59.8915 117.809 59.9251 117.847 59.9544L118.079 60.2622C118.079 60.2622 118.077 60.2727 118.073 60.2936C118.073 60.2936 118.083 60.2957 118.104 60.2999L118.01 60.281C118.014 60.26 118.006 60.2475 117.985 60.2433C117.964 60.2391 117.953 60.237 117.953 60.237C117.949 60.1491 117.933 60.124 117.903 60.1616C117.878 60.1783 117.855 60.1845 117.834 60.1803L117.84 60.3121L117.972 60.4692C117.972 60.4692 117.97 60.4796 117.966 60.5006C117.982 60.5257 118.001 60.5403 118.022 60.5446C117.98 60.5361 117.943 60.5068 117.909 60.4566L117.878 60.4502C117.878 60.4502 117.857 60.446 117.815 60.4376L117.827 60.538C117.986 60.6135 118.091 60.689 118.141 60.7644L118.254 61.0155L118.304 61.0909C118.341 61.1202 118.335 61.1516 118.285 61.185C118.26 61.2017 118.226 61.2059 118.184 61.1974L118.015 61.0654L117.752 60.9145C117.676 60.8558 117.649 60.883 117.67 60.996L117.664 61.0273L117.639 60.9896C117.626 60.9436 117.576 60.9226 117.488 60.9267L116.503 60.9568L115.58 60.9996L115.31 61.0432C114.98 61.0637 114.662 61.0758 114.356 61.0796C114.248 61.0795 114.137 61.0898 114.024 61.1106C113.915 61.1104 113.785 61.1061 113.635 61.0975C113.593 61.0891 113.515 61.0953 113.402 61.1161C113.294 61.1159 113.187 61.1053 113.082 61.0843L112.976 61.1281C112.812 61.3998 112.69 61.5712 112.611 61.6422L112.454 61.7738C112.278 61.9995 112.083 62.2649 111.869 62.5701C111.781 62.6829 111.689 62.8167 111.593 62.9714C111.521 63.1093 111.416 63.2515 111.278 63.3977C110.951 63.9412 110.75 64.2924 110.674 64.4513C110.637 64.5307 110.597 64.6206 110.555 64.721C110.517 64.8004 110.486 64.9029 110.46 65.0284C110.423 65.1078 110.448 65.1455 110.535 65.1414C110.607 65.1122 110.663 65.1018 110.705 65.1103C110.772 65.102 110.816 65.0999 110.837 65.1041L110.868 65.1105C110.847 65.1063 110.835 65.1146 110.83 65.1355L110.485 65.2292C110.464 65.225 110.441 65.2313 110.416 65.248C110.416 65.248 110.406 65.2459 110.385 65.2416L110.51 65.2669L110.767 65.2861L110.83 65.2987L110.793 65.3237L110.491 65.361C110.424 65.3693 110.376 65.3922 110.347 65.4299C110.322 65.4466 110.313 65.4884 110.322 65.5553C110.317 65.5763 110.313 65.5972 110.309 65.6181C110.33 65.6223 110.338 65.6349 110.334 65.6558C110.326 65.6976 110.363 65.7269 110.447 65.7438L110.704 65.7629C110.771 65.7546 110.848 65.7485 110.936 65.7444C111.049 65.7236 111.158 65.7238 111.263 65.7448L111.325 65.7574C111.346 65.7617 111.367 65.7659 111.388 65.7701C111.43 65.7785 111.459 65.7953 111.476 65.8204C111.543 65.9209 111.612 65.9565 111.683 65.9273L112.719 65.8094L113.158 65.7347L113.221 65.7473C113.263 65.7557 113.329 65.7474 113.422 65.7225C113.514 65.6975 113.604 65.6829 113.691 65.6789C113.738 65.6664 113.807 65.6476 113.899 65.6227C114.016 65.581 114.129 65.5602 114.238 65.5603C114.259 65.5645 114.405 65.5396 114.677 65.4856C114.811 65.469 114.913 65.4461 114.985 65.4169C115.077 65.3919 115.156 65.3753 115.223 65.367C115.395 65.3798 115.483 65.3757 115.487 65.3548L115.531 65.2984C115.552 65.3026 115.56 65.3152 115.556 65.3361C115.552 65.357 115.549 65.3674 115.549 65.3674C115.625 65.3173 115.654 65.3341 115.637 65.4178C115.654 65.4429 115.673 65.4576 115.694 65.4618C115.736 65.4702 115.759 65.4639 115.763 65.443L115.794 65.4493L115.857 65.462L115.863 65.4306L115.876 65.3679C115.88 65.3469 115.893 65.3386 115.914 65.3428L115.907 65.3742L115.888 65.4683C115.888 65.4683 115.863 65.485 115.813 65.5184L115.8 65.5811C115.796 65.6021 115.792 65.623 115.788 65.6439C115.809 65.6481 115.817 65.6607 115.813 65.6816C115.829 65.7067 115.884 65.7611 115.976 65.8449C115.997 65.8492 116.005 65.8617 116.001 65.8826C116.051 66.0668 116.107 66.1652 116.17 66.1778C116.191 66.182 116.203 66.1737 116.207 66.1527C116.233 66.136 116.256 66.1298 116.277 66.134L116.314 66.109C116.314 66.109 116.312 66.1194 116.308 66.1403C116.329 66.1445 116.35 66.1487 116.371 66.153L116.364 66.1843L116.339 66.3098C116.36 66.314 116.396 66.2994 116.446 66.266C116.496 66.2326 116.523 66.2054 116.527 66.1845C116.527 66.1845 116.53 66.1741 116.534 66.1532C116.559 66.1365 116.574 66.1176 116.578 66.0967C116.599 66.1009 116.607 66.1135 116.603 66.1344C116.599 66.1553 116.607 66.1679 116.628 66.1721L116.622 66.2035C116.571 66.2369 116.55 66.2871 116.559 66.354C116.575 66.3791 116.577 66.4231 116.565 66.4858C116.586 66.5988 116.642 66.6428 116.734 66.6178C116.801 66.6095 116.853 66.6201 116.891 66.6494C116.937 66.7457 116.916 66.8503 116.828 66.9631C116.731 67.009 116.685 67.0759 116.689 67.1637C116.693 67.2516 116.693 67.306 116.689 67.3269L116.626 67.6406L116.588 67.6657C116.588 67.6657 116.578 67.6636 116.557 67.6594C116.536 67.6552 116.528 67.6426 116.532 67.6217C116.473 67.5881 116.44 67.5379 116.432 67.4709C116.419 67.4249 116.4 67.4102 116.375 67.4269C116.266 67.5356 116.103 67.5898 115.886 67.5895C115.773 67.6103 115.639 67.6268 115.484 67.6392C115.35 67.6557 115.203 67.6807 115.044 67.7139C114.911 67.7305 114.762 67.7659 114.599 67.82L114.567 67.8137C114.53 67.7844 114.486 67.7864 114.436 67.8198C114.385 67.8532 114.35 67.8678 114.329 67.8636L114.291 67.8887L114.166 67.8634C114.132 67.922 114.082 67.9554 114.015 67.9636C113.948 67.9719 113.904 67.974 113.883 67.9698L113.689 67.9632C113.555 67.9798 113.444 68.0445 113.356 68.1574L113.324 68.151C113.262 68.1384 113.174 68.1425 113.061 68.1633C112.948 68.184 112.858 68.1986 112.791 68.2068L112.515 68.2818C112.494 68.2776 112.458 68.2922 112.408 68.3256C112.345 68.313 112.314 68.3066 112.314 68.3066L112.251 68.294C112.188 68.2814 112.111 68.2876 112.019 68.3125C111.923 68.3584 111.841 68.3855 111.774 68.3938L111.63 68.4627L111.391 68.5126L111.297 68.4936ZM110.861 65.9577L110.936 65.9076L110.873 65.8949C110.811 65.8823 110.765 65.8948 110.735 65.9324L110.698 65.9575L110.76 65.9701L110.861 65.9577ZM109.521 63.2072L109.578 63.088C109.582 63.0671 109.574 63.0546 109.553 63.0504L109.547 63.0817C109.521 63.0984 109.503 63.1382 109.49 63.2009L109.521 63.2072ZM111.168 65.889C111.273 65.9101 111.348 65.9144 111.394 65.9019L111.426 65.9082L111.401 65.8705L111.168 65.889L111.137 65.8827C111.137 65.8827 111.135 65.8932 111.131 65.9141C111.152 65.9183 111.164 65.9099 111.168 65.889ZM109.773 62.7682C109.823 62.7348 109.855 62.6867 109.867 62.624L109.873 62.5926L109.842 62.5863L109.754 62.6992L109.741 62.7619L109.773 62.7682ZM113.47 66.94C113.5 66.9024 113.525 66.8857 113.546 66.8899C113.567 66.8941 113.59 66.8879 113.615 66.8712L113.991 66.7838C114.054 66.7964 114.131 66.7902 114.224 66.7652L114.268 66.7088L114.198 66.7276C113.981 66.7273 113.814 66.748 113.696 66.7897C113.646 66.8231 113.575 66.8523 113.483 66.8773C113.462 66.8731 113.447 66.8919 113.439 66.9337L113.47 66.94ZM113.59 66.344C113.728 66.3065 113.864 66.2795 113.998 66.2629C114.132 66.2463 114.245 66.2256 114.337 66.2006L114.406 66.1818C114.364 66.1734 114.344 66.1692 114.344 66.1692L113.91 66.2126C113.864 66.2251 113.806 66.2459 113.735 66.2751C113.689 66.2876 113.63 66.3085 113.559 66.3377L113.527 66.3313L113.559 66.3377L113.59 66.344ZM114.758 66.0568C114.913 66.0444 115.038 66.0153 115.135 65.9694L115.26 65.9946L115.109 65.9317C114.967 65.9901 114.852 66.0213 114.764 66.0254C114.764 66.0254 114.762 66.0359 114.758 66.0568C114.758 66.0568 114.747 66.0547 114.727 66.0505L114.758 66.0568ZM122.886 55.3544L122.899 55.2917C122.911 55.229 122.93 55.1892 122.955 55.1725L122.987 55.1788L122.911 55.3921L122.88 55.3858L122.886 55.3544ZM120.053 74.6958L120.016 74.5577C119.991 74.4656 119.985 74.3882 119.997 74.3255C120.031 73.9406 120.065 73.6645 120.099 73.4972L120.13 73.5035L120.206 72.9639L120.338 72.6315C120.372 72.4641 120.406 72.3512 120.439 72.2927C120.515 72.1338 120.559 72.023 120.571 71.9602L120.584 71.8975C120.563 71.8933 120.553 71.8912 120.553 71.8912C120.548 71.9121 120.546 71.9226 120.546 71.9226C120.521 71.9393 120.504 71.9685 120.496 72.0104C120.467 72.048 120.402 72.1546 120.301 72.3302L120.295 72.3615C120.307 72.4076 120.263 72.464 120.163 72.5308L120.043 72.8005L120.037 72.8319L120.012 72.7942L120.068 72.675C120.077 72.6332 120.071 72.6102 120.05 72.606L120.031 72.5369L119.987 72.5934L119.93 72.7125C119.922 72.7543 119.939 72.7795 119.98 72.7879L119.974 72.8193L119.866 73.5157L119.829 73.5408L119.835 73.5094L119.848 72.9572L119.88 72.6371C119.926 72.4071 120.008 72.2168 120.126 72.0664L120.17 72.0099C120.174 71.989 120.186 71.9807 120.207 71.9849L120.195 72.0476C120.19 72.0685 120.155 72.1375 120.088 72.2546L120.106 72.3236L120.132 72.3613L120.182 72.4367C120.19 72.3949 120.194 72.374 120.194 72.374L120.201 72.3426C120.213 72.2799 120.236 72.2192 120.27 72.1607C120.324 72.1064 120.345 72.0562 120.333 72.0101C120.379 71.9977 120.408 71.96 120.421 71.8973C120.454 71.8388 120.475 71.7886 120.484 71.7468C120.538 71.6924 120.589 71.6046 120.635 71.4834C120.698 71.3872 120.746 71.3099 120.779 71.2514C120.893 71.013 120.991 70.8479 121.075 70.7559L121.251 70.5302C121.377 70.3379 121.448 70.2 121.465 70.1163L121.484 70.0222C121.501 69.9386 121.53 69.8465 121.572 69.7462C121.635 69.65 121.671 69.5811 121.679 69.5392C121.687 69.4974 121.702 69.4786 121.723 69.4828C121.752 69.4452 121.794 69.3992 121.849 69.3449C121.903 69.2906 121.96 69.2258 122.018 69.1506C122.073 69.0962 122.106 69.0377 122.119 68.975C122.153 68.9164 122.186 68.8579 122.22 68.7994L122.226 68.768C122.197 68.8056 122.174 68.8119 122.157 68.7867C122.161 68.7658 122.153 68.7533 122.132 68.7491C122.082 68.7825 122.054 68.8096 122.05 68.8305C122.021 68.8682 121.991 68.9058 121.962 68.9434C121.954 68.9852 121.935 69.0249 121.905 69.0626C121.83 69.1127 121.792 69.1921 121.792 69.3009C121.784 69.3427 121.759 69.3594 121.717 69.351L121.692 69.3133L121.704 69.2506C121.738 69.192 121.774 69.1231 121.811 69.0436C121.853 68.9433 121.902 68.8659 121.956 68.8116C122.132 68.5859 122.268 68.3957 122.365 68.241C122.432 68.124 122.497 68.0174 122.56 67.9212C122.643 67.8293 122.717 67.7352 122.78 67.6391L122.824 67.5827L122.83 67.5513L122.799 67.545C122.727 67.5742 122.658 67.6473 122.591 67.7644C122.562 67.802 122.522 67.8375 122.472 67.8709C122.447 67.8876 122.422 67.9043 122.396 67.921C122.329 68.0381 122.289 68.128 122.277 68.1907L122.195 68.2722C122.191 68.2931 122.199 68.3057 122.22 68.3099L122.214 68.3412L121.975 68.5543C121.921 68.6086 121.852 68.6818 121.768 68.7737C121.705 68.8698 121.657 68.9472 121.623 69.0057L121.202 69.639L120.957 70.0466L120.906 70.1344L120.63 70.5357C120.625 70.5566 120.615 70.5545 120.598 70.5294C120.577 70.5252 120.569 70.5126 120.573 70.4917L120.605 70.3349L120.636 70.3412C120.67 70.3914 120.693 70.3852 120.705 70.3225C120.718 70.2597 120.737 70.22 120.762 70.2033C120.779 70.1196 120.825 69.9984 120.9 69.8395L120.907 69.8081C120.919 69.7454 120.98 69.6597 121.089 69.551L121.171 69.4695C121.175 69.4486 121.19 69.4298 121.215 69.4131C121.244 69.3755 121.269 69.3588 121.29 69.363C121.311 69.3672 121.326 69.3484 121.334 69.3066L121.34 69.2752C121.357 69.1916 121.42 69.0954 121.529 68.9868C121.642 68.7484 121.787 68.5164 121.963 68.2907C122.051 68.1779 122.097 68.111 122.101 68.0901L122.265 67.7639C122.298 67.7054 122.334 67.6364 122.372 67.557C122.414 67.4566 122.46 67.3897 122.51 67.3563C122.544 67.2978 122.567 67.2372 122.579 67.1744C122.617 67.095 122.661 67.0386 122.711 67.0051L122.724 66.9424C122.682 66.934 122.659 66.9402 122.655 66.9611C122.634 66.9569 122.621 66.9653 122.617 66.9862C122.596 67.0908 122.546 67.1786 122.466 67.2496C122.387 67.3206 122.332 67.3749 122.303 67.4125L122.209 67.5568C122.192 67.6404 122.152 67.6759 122.089 67.6633C122.027 67.6507 121.987 67.6862 121.97 67.7698C121.966 67.7908 121.951 67.8096 121.926 67.8263C121.901 67.843 121.878 67.8492 121.857 67.845L121.775 67.9265C121.389 68.5452 121.067 69.0134 120.807 69.331L120.499 69.726C120.495 69.7469 120.482 69.7553 120.461 69.7511L120.436 69.7134C120.445 69.6715 120.44 69.6381 120.424 69.6129C120.491 69.4959 120.552 69.4102 120.606 69.3559C120.744 69.1008 120.833 68.9336 120.87 68.8541L120.877 68.8228L120.839 68.8478L120.663 69.0735C120.537 69.157 120.428 69.2657 120.336 69.3995C120.336 69.3995 120.326 69.3973 120.305 69.3931C120.305 69.3931 120.303 69.4036 120.298 69.4245L120.305 69.3931L120.286 69.3241L120.273 69.3868C120.19 69.4788 120.085 69.6209 119.959 69.8132L119.89 69.8319C119.911 69.8361 119.913 69.8257 119.896 69.8005C119.896 69.8005 119.907 69.8026 119.928 69.8069C119.995 69.6898 120.035 69.5999 120.047 69.5372C120.102 69.4828 120.167 69.3762 120.242 69.2173L120.249 69.186C120.324 69.1359 120.383 69.0606 120.425 68.9603C120.492 68.8432 120.54 68.7659 120.569 68.7282L120.582 68.6655L120.594 68.6028L120.525 68.6215C120.483 68.7219 120.393 68.8452 120.255 68.9914C120.226 69.029 120.196 69.0667 120.167 69.1043C120.142 69.121 120.115 69.1481 120.085 69.1858C120.035 69.2192 120.01 69.2359 120.01 69.2359L120.029 69.1418L120.205 68.9161C120.238 68.8575 120.272 68.799 120.306 68.7405C120.343 68.661 120.379 68.592 120.413 68.5335L120.545 68.3642C120.595 68.3308 120.601 68.2994 120.563 68.2701C120.543 68.2659 120.532 68.2638 120.532 68.2638C120.536 68.2429 120.538 68.2324 120.538 68.2324L120.714 68.0067L120.721 67.9754L120.689 67.969L120.608 68.0505L120.57 68.0756L120.583 68.0128C120.612 67.9752 120.675 67.8791 120.771 67.7244L121.444 66.8153L121.966 66.0064C122.02 65.952 122.069 65.8747 122.11 65.7743C122.178 65.6573 122.228 65.5695 122.261 65.511C122.437 65.2852 122.561 65.1034 122.632 64.9654C122.695 64.8693 122.771 64.7648 122.859 64.6519C122.972 64.5224 123.049 64.4074 123.091 64.3071C123.385 63.9309 123.594 63.6467 123.72 63.4544C123.925 63.191 124.095 62.9423 124.229 62.7082C124.275 62.5869 124.343 62.4699 124.431 62.357C124.544 62.2275 124.617 62.1334 124.651 62.0749L125.305 61.0967L125.701 60.5889C125.73 60.5513 125.759 60.5136 125.789 60.476C125.822 60.4175 125.845 60.3569 125.858 60.2941C126.151 59.918 126.34 59.6295 126.424 59.4288L126.606 59.1717C126.64 59.1132 126.686 59.0463 126.744 58.9711C126.807 58.8749 126.86 58.7767 126.902 58.6763L127.449 57.9051C127.516 57.788 127.69 57.5728 127.97 57.2594C128.075 57.0629 128.14 56.9562 128.165 56.9395C128.22 56.8852 128.205 56.8496 128.121 56.8328L127.87 56.7823C127.444 56.7399 127.111 56.7165 126.873 56.712C126.53 56.6864 126.249 56.6735 126.032 56.6733C125.714 56.631 125.31 56.6368 124.821 56.6905C124.557 56.7028 124.323 56.7317 124.118 56.7775C123.917 56.8024 123.749 56.8231 123.615 56.8396L122.511 56.9763C122.486 56.993 122.461 57.0097 122.435 57.0264C122.268 56.9927 122.092 57.0009 121.908 57.0508C121.745 57.105 121.617 57.1446 121.525 57.1696C121.333 57.2614 121.19 57.3198 121.098 57.3448C121.048 57.3782 121.023 57.3949 121.023 57.3949C120.998 57.4116 120.964 57.4157 120.922 57.4073C120.943 57.4115 120.958 57.3927 120.966 57.3509L121.299 57.1567L121.802 56.9315C121.827 56.9148 121.862 56.9002 121.908 56.8877C121.954 56.8752 121.98 56.8585 121.984 56.8376L122.241 56.6935L122.279 56.6685L122.882 56.4308L123.02 56.3933C123.041 56.3975 123.076 56.3829 123.127 56.3495C123.147 56.3537 123.158 56.3558 123.158 56.3558C123.162 56.3349 123.164 56.3244 123.164 56.3244L123.227 56.3371C123.269 56.3455 123.313 56.3435 123.359 56.331C123.409 56.2976 123.457 56.2746 123.503 56.2621L123.51 56.2307L123.478 56.2244L123.19 56.199L123.133 56.155L123.146 56.0922L123.579 55.8857L123.623 55.8292L123.899 55.7543L123.906 55.7229L123.874 55.7166L123.811 55.704C123.811 55.704 123.809 55.7144 123.805 55.7353C123.805 55.7353 123.795 55.7332 123.774 55.729L123.667 55.7728C123.667 55.7728 123.657 55.7707 123.636 55.7665C123.636 55.7665 123.638 55.756 123.642 55.7351C123.6 55.7267 123.579 55.7225 123.579 55.7225L123.215 55.7471C123.169 55.7596 123.115 55.7596 123.052 55.7469L123.021 55.7406L123.065 55.6842L123.196 55.6781L123.31 55.6029L123.347 55.5779C123.46 55.5571 123.634 55.505 123.868 55.4216L123.9 55.4279C123.983 55.4448 124.048 55.447 124.094 55.4345C124.144 55.4011 124.278 55.3845 124.496 55.3848L124.596 55.3724C124.626 55.3347 124.651 55.318 124.672 55.3222C124.734 55.3349 124.799 55.337 124.866 55.3288C124.937 55.2996 125.015 55.2934 125.098 55.3102L125.13 55.3166L125.193 55.3292C125.218 55.3125 125.241 55.3062 125.262 55.3104C125.303 55.3189 125.337 55.3147 125.362 55.298C125.383 55.3022 125.431 55.2793 125.507 55.2292C125.557 55.1958 125.59 55.1916 125.607 55.2167C125.603 55.2377 125.601 55.2481 125.601 55.2481C125.622 55.2523 125.634 55.244 125.638 55.2231L125.751 55.1479C125.756 55.127 125.747 55.1144 125.726 55.1102L125.469 55.0911L124.653 55.09C124.632 55.0858 124.576 55.0962 124.484 55.1212L124.452 55.1149L124.49 55.0898L124.66 55.0586L124.704 55.0022C124.678 55.0189 124.655 55.0252 124.634 55.021L124.54 55.002C124.524 54.9769 124.494 54.9601 124.453 54.9517L123.925 54.9761L123.894 54.9698L123.932 54.9448L124.333 54.8951L124.691 54.9018L124.729 54.8767L124.697 54.8704C124.676 54.8662 124.656 54.862 124.635 54.8578C124.639 54.8369 124.628 54.8348 124.603 54.8515C124.541 54.8388 124.486 54.8388 124.44 54.8513L124.377 54.8386L124.446 54.8199C124.672 54.7783 124.84 54.7576 124.949 54.7578L125.018 54.739L124.955 54.7264C124.85 54.7054 124.765 54.699 124.698 54.7073C124.631 54.7155 124.555 54.7113 124.472 54.6944C124.388 54.6776 124.323 54.6754 124.277 54.6879C124.21 54.6962 124.114 54.6877 123.989 54.6624L123.995 54.6311L124.422 54.619C124.447 54.6023 124.47 54.5961 124.491 54.6003C124.532 54.6087 124.566 54.6046 124.591 54.5879C124.754 54.5337 124.968 54.5005 125.231 54.4883C125.629 54.4595 125.871 54.4431 125.959 54.439C125.98 54.4432 125.993 54.4349 125.997 54.4139L125.934 54.4013C125.867 54.4096 125.767 54.422 125.633 54.4386C125.524 54.4385 125.42 54.4174 125.319 54.3754C125.303 54.3503 125.282 54.3461 125.257 54.3628C125.257 54.3628 125.246 54.3607 125.225 54.3565L125.332 54.3127L125.47 54.2752C125.654 54.2252 125.853 54.2109 126.066 54.232C126.284 54.2323 126.426 54.2283 126.493 54.22L126.888 54.2017L126.989 54.1893C127.081 54.1643 127.158 54.1581 127.221 54.1708C127.485 54.1585 127.64 54.1462 127.686 54.1337L127.849 54.1339L128.006 54.1655L128.068 54.1781L128.169 54.1657L128.081 54.1154L127.686 53.9705L127.648 53.9956L127.686 53.9705L128.094 54.0526L128.282 54.0905L128.32 54.0655C128.349 54.0278 128.395 54.0154 128.458 54.028C128.571 54.0072 128.736 53.997 128.953 53.9972L129.499 54.0419C129.721 54.0212 130.05 54.0112 130.485 54.0117C130.619 53.9952 130.857 53.9997 131.2 54.0252C131.313 54.0044 131.455 54.0004 131.627 54.0132C131.803 54.005 131.934 53.9989 132.022 53.9949C132.395 53.9828 132.719 53.9937 132.995 54.0275C133.125 54.0318 133.244 54.0341 133.353 54.0342C133.487 54.0176 133.618 54.0115 133.748 54.0159C133.853 54.0369 133.97 54.0496 134.099 54.054C134.233 54.0374 134.363 54.0418 134.489 54.067L134.89 54.1805C134.969 54.2183 135.064 54.2372 135.172 54.2373L135.348 54.338L135.492 54.4323L135.555 54.4449C135.626 54.5245 135.722 54.5874 135.843 54.6336C135.965 54.6797 136.046 54.707 136.088 54.7155C136.13 54.7239 136.239 54.7784 136.414 54.879C136.59 54.9797 136.717 55.1033 136.797 55.2498C136.838 55.367 136.972 55.568 137.197 55.8528C137.273 55.9114 137.335 55.9785 137.385 56.0538C137.436 56.1292 137.488 56.1941 137.542 56.2486C137.538 56.2695 137.552 56.3051 137.586 56.3553C137.636 56.4307 137.653 56.5102 137.636 56.5939L137.61 56.7193C137.598 56.7821 137.562 56.7967 137.504 56.7631C137.487 56.738 137.451 56.7526 137.397 56.8069C137.347 56.8403 137.317 56.878 137.309 56.9198C137.301 56.9616 137.282 57.0013 137.252 57.039C137.244 57.0808 137.246 57.1247 137.258 57.1708C137.296 57.3089 137.308 57.4093 137.296 57.472C137.279 57.5557 137.277 57.6205 137.289 57.6666C137.285 57.6875 137.295 57.7984 137.32 57.9992C137.308 58.062 137.249 58.0828 137.144 58.0618L136.743 57.7851C136.68 57.7725 136.626 57.7724 136.58 57.7849C136.517 57.7723 136.488 57.7555 136.492 57.7346C136.279 57.4958 136.083 57.3366 135.903 57.2569C135.828 57.1982 135.675 57.1457 135.445 57.0994C135.219 57.0322 134.953 57.0005 134.648 57.0043C134.347 56.9871 134.131 56.9764 134.002 56.9721L132.922 56.9832L132.332 56.995L132.238 56.9761L132.288 57.0515L132.344 57.2586C132.378 57.3089 132.395 57.334 132.395 57.334C132.511 57.5099 132.511 57.6731 132.394 57.8235L132.419 57.8612C132.427 57.9282 132.406 57.9783 132.356 58.0117C132.31 58.0242 132.274 58.0388 132.249 58.0555C132.245 58.0765 132.233 58.0848 132.212 58.0806C132.191 58.0764 132.18 58.0743 132.18 58.0743L131.986 57.9046L131.892 57.8856C131.871 57.8814 131.856 57.9002 131.848 57.9421C131.793 57.9964 131.689 58.0297 131.534 58.0421C131.513 58.0379 131.465 58.0608 131.389 58.1109C131.36 58.1485 131.232 58.2969 131.006 58.556C130.826 58.6939 130.629 58.9153 130.415 59.2205L129.73 60.1924L129.076 61.0074L128.548 61.6845C128.418 61.8977 128.293 62.09 128.171 62.2614C128.054 62.4118 127.949 62.5539 127.857 62.6877C127.568 63.043 127.404 63.2603 127.366 63.3398C127.337 63.3774 127.306 63.4255 127.272 63.484C127.238 63.5425 127.205 63.601 127.171 63.6596L126.914 63.9668C126.792 64.1381 126.715 64.2531 126.681 64.3116L126.404 64.7129L125.996 65.2835L125.48 65.8979C125.359 66.0692 125.242 66.2197 125.128 66.3493C125.036 66.483 124.946 66.6063 124.858 66.7192L124.173 67.5279C124.009 67.7996 123.844 68.0274 123.676 68.2113C123.433 68.5541 123.261 68.8133 123.161 68.9888C123.127 69.0474 123.089 69.1268 123.047 69.2272C123.01 69.3066 122.947 69.4028 122.859 69.5156C122.796 69.6118 122.72 69.7163 122.632 69.8291C122.54 69.9629 122.448 70.0967 122.356 70.2304L121.476 71.3589L121.218 71.8293L120.885 72.3497C120.65 72.7595 120.513 73.0584 120.476 73.2466L120.248 74.2128L120.21 74.7274C120.206 74.7483 120.193 74.7566 120.172 74.7524L120.179 74.7211C120.179 74.7211 120.181 74.7106 120.185 74.6897C120.185 74.6897 120.172 74.698 120.147 74.7147L120.154 74.6834C120.133 74.6792 120.12 74.6875 120.116 74.7084L120.072 74.7649L120.053 74.6958ZM120.51 71.1318C120.627 70.9813 120.705 70.8663 120.742 70.7869L120.811 70.7682C120.757 70.8225 120.667 70.9458 120.541 71.1381L120.497 71.1945L120.51 71.1318ZM120.811 70.7682C120.824 70.7054 120.822 70.6615 120.805 70.6364L120.849 70.5799L120.868 70.649L120.811 70.7682ZM122.276 68.6802L122.396 68.5737L122.377 68.5046C122.373 68.5255 122.36 68.5339 122.339 68.5297L122.245 68.6739L122.239 68.7053L122.276 68.6802ZM121.959 56.4735C122.001 56.4819 122.026 56.4652 122.035 56.4234C122.097 56.436 122.141 56.434 122.166 56.4173L122.198 56.4236L122.455 56.2796C122.531 56.2295 122.641 56.2192 122.788 56.2487L122.844 56.2927L122.782 56.28L122.606 56.3426C122.572 56.4011 122.524 56.424 122.461 56.4114C122.419 56.403 122.361 56.4238 122.285 56.4739L122.053 56.4925C122.028 56.5092 122.005 56.5154 121.984 56.5112C121.988 56.4903 121.98 56.4777 121.959 56.4735ZM123.409 56.08C123.46 56.0466 123.495 56.032 123.516 56.0362L123.491 55.9985L123.384 56.0423L123.409 56.08ZM123.9 55.1016L123.931 55.1079L124.195 55.0957L124.226 55.102L124.189 55.1271C124.122 55.1354 124.036 55.129 123.931 55.1079L123.9 55.1016ZM141.278 74.4643C141.303 74.3388 141.276 74.2571 141.197 74.2194C141.134 74.2068 141.107 74.1795 141.115 74.1377C141.116 74.0289 141.074 73.9117 140.99 73.7861C140.94 73.7107 140.907 73.6061 140.89 73.4722C140.895 73.3425 140.882 73.2421 140.853 73.1709L140.803 72.9324C140.778 72.8403 140.787 72.6897 140.829 72.4806C140.825 72.3927 140.829 72.3174 140.842 72.2546C140.875 72.1961 140.888 72.1334 140.88 72.0664L140.899 71.9723C140.924 71.8468 140.98 71.7277 141.068 71.6148C141.215 71.4267 141.454 71.3224 141.784 71.3019C141.851 71.2936 141.914 71.3063 141.972 71.3398C142.035 71.3525 142.088 71.363 142.129 71.3714L142.845 71.3849L142.977 71.2156L143.229 70.6134C143.287 70.5382 143.333 70.4713 143.367 70.4128C143.405 70.3333 143.44 70.2644 143.474 70.2058C143.495 70.21 143.497 70.1996 143.48 70.1745C143.484 70.1535 143.474 70.1514 143.449 70.1681L143.455 70.1368C143.468 70.074 143.487 70.0343 143.512 70.0176L143.518 69.9862L143.487 69.9799C143.399 69.984 143.374 70.0551 143.411 70.1932C143.428 70.2183 143.407 70.2685 143.348 70.3437L143.317 70.3374C143.342 70.3207 143.344 70.3103 143.323 70.306C143.327 70.2851 143.332 70.2642 143.336 70.2433C143.332 70.2642 143.317 70.283 143.292 70.2997C143.271 70.2955 143.26 70.2934 143.26 70.2934C143.302 70.4106 143.268 70.5235 143.16 70.6322L143.034 70.9333C143.029 70.9542 143.017 70.9625 142.996 70.9583C142.996 70.9583 142.988 70.9457 142.971 70.9206C142.971 70.9206 142.969 70.9311 142.965 70.952C142.965 70.952 142.954 70.9499 142.933 70.9457L142.952 70.8516L142.984 70.6947C143.017 70.5274 143.08 70.3769 143.173 70.2431C143.235 70.1469 143.275 70.057 143.292 69.9734C143.33 69.8939 143.353 69.8333 143.361 69.7915C143.42 69.7163 143.456 69.6473 143.468 69.5845C143.489 69.5887 143.506 69.5595 143.519 69.4967L143.525 69.4654L143.5 69.4277C143.383 69.5781 143.305 69.6931 143.267 69.7725L142.777 70.5878L142.739 70.6128L142.745 70.5814C142.733 70.5354 142.752 70.4957 142.802 70.4623C142.806 70.4414 142.81 70.4204 142.815 70.3995C142.84 70.3828 142.844 70.3619 142.827 70.3368L142.834 70.3054C142.875 70.3138 142.88 70.2929 142.846 70.2427L142.89 70.1863L142.783 70.2301L142.746 70.2551L142.758 70.1924C142.813 70.138 142.844 70.09 142.853 70.0481C142.886 69.9896 142.905 69.9499 142.909 69.929L142.891 69.8599C142.886 69.8808 142.874 69.8892 142.853 69.885L142.727 70.0229C142.723 70.0438 142.71 70.0521 142.69 70.0479L142.696 70.0166L142.727 69.8597C142.753 69.7342 142.801 69.6025 142.872 69.4645C142.944 69.3266 142.996 69.2283 143.03 69.1698C143.055 69.1531 143.107 69.0548 143.187 68.875L143.482 68.3796L143.602 68.1099C143.615 68.0472 143.636 67.997 143.665 67.9594C143.799 67.7252 143.889 67.5475 143.935 67.4263C143.952 67.3426 143.978 67.2715 144.011 67.213C144.045 67.1545 144.078 67.0959 144.112 67.0374C144.271 66.7866 144.437 66.5044 144.609 66.1908L145.042 65.4948C145.177 65.2606 145.286 65.0976 145.369 65.0057C145.416 64.8844 145.502 64.7276 145.627 64.5353L145.778 64.2719C145.954 63.9374 146.074 63.7221 146.137 63.626C146.17 63.5674 146.256 63.4651 146.395 63.3188L146.615 62.8735L146.942 62.3844L147.231 61.9204C147.265 61.8618 147.306 61.8159 147.357 61.7825C147.411 61.7281 147.455 61.6717 147.489 61.6132L147.495 61.5818L147.52 61.4563C147.495 61.473 147.462 61.4772 147.42 61.4688L147.181 61.5187C147.114 61.5269 147.087 61.4997 147.1 61.437C147.104 61.4161 147.112 61.3742 147.125 61.3115C147.163 61.232 147.178 61.1589 147.169 61.0919C147.182 61.0292 147.155 60.9475 147.088 60.847L147.051 60.7089C147.063 60.6462 147.063 60.5918 147.051 60.5458C147.03 60.5416 147.021 60.529 147.026 60.5081C147.051 60.4914 147.065 60.4726 147.07 60.4516C147.124 60.3973 147.145 60.2928 147.133 60.1379C147.15 60.0543 147.171 60.0041 147.196 59.9874C147.326 59.883 147.366 59.7387 147.316 59.5545L147.197 59.3347C147.151 59.2384 147.165 59.1652 147.241 59.1151C147.53 58.9774 147.674 58.9086 147.674 58.9086C147.724 58.8752 147.779 58.8209 147.837 58.7456C147.888 58.7122 147.913 58.6955 147.913 58.6955L148.302 58.5454L148.666 58.5208L149.156 58.5214C149.331 58.5132 149.488 58.5448 149.626 58.6161C149.714 58.612 149.902 58.5955 150.191 58.5666C150.212 58.5708 150.243 58.5772 150.285 58.5856C150.352 58.5773 150.394 58.5857 150.411 58.6108C150.703 58.6698 150.931 58.7266 151.095 58.7811C151.157 58.7938 151.216 58.8273 151.27 58.8818C151.35 58.9195 151.419 58.9552 151.477 58.9887L152.073 59.4351C152.115 59.4435 152.152 59.4728 152.186 59.5231C152.294 59.632 152.407 59.72 152.524 59.7871C152.8 59.9297 153.013 60.0596 153.164 60.177L153.258 60.1959C153.279 60.2001 153.289 60.2023 153.289 60.2023C153.314 60.1855 153.335 60.1898 153.352 60.2149C153.49 60.2862 153.693 60.414 153.96 60.5985L154.587 61.2143C154.658 61.2939 154.787 61.5158 154.975 61.88C155.038 62.0014 155.092 62.1103 155.138 62.2066C155.184 62.3028 155.221 62.3866 155.251 62.4577L155.313 62.6335C155.397 62.8679 155.501 63.2153 155.626 63.6757L155.669 63.9456L155.781 64.8495C155.794 64.8955 155.806 64.9959 155.818 65.1507C155.831 65.3056 155.814 65.4436 155.768 65.5649C155.767 65.6736 155.761 65.8138 155.748 65.9853C155.74 66.1359 155.714 66.3158 155.672 66.5249C155.634 66.7132 155.597 66.847 155.559 66.9264L155.59 66.9327C155.477 67.1711 155.328 67.5328 155.143 68.0179C155.126 68.1015 155.101 68.1726 155.068 68.2312C155.038 68.2688 155.009 68.3064 154.98 68.344C154.954 68.3607 154.908 68.4276 154.841 68.5447C154.799 68.645 154.711 68.7579 154.577 68.8832C154.464 69.0128 154.378 69.1152 154.32 69.1904L153.993 69.5163C153.959 69.5748 153.917 69.6208 153.867 69.6542C153.821 69.6667 153.783 69.6918 153.754 69.7294L153.584 69.9237L152.849 70.4939L151.995 71.0074L151.725 71.2142L151.317 71.4584L150.871 71.7277C150.461 71.928 150.109 72.1074 149.816 72.266C149.531 72.3828 149.316 72.4809 149.169 72.5602C149.215 72.5477 149.058 72.6249 148.698 72.7918L148.033 73.0169L147.549 73.148L146.312 73.6172L145.791 73.7734C145.695 73.8193 145.555 73.8672 145.371 73.9172C145.094 73.9921 144.885 74.0588 144.743 74.1172C144.676 74.1255 144.571 74.1588 144.429 74.2172L144.165 74.2294L143.958 74.2857L143.908 74.3735C143.899 74.4153 143.874 74.432 143.832 74.4236L143.801 74.4173C143.726 74.3586 143.678 74.3271 143.657 74.3229C143.594 74.3103 143.54 74.3102 143.494 74.3227C143.469 74.3394 143.433 74.354 143.387 74.3665L142.841 74.4851C142.753 74.4891 142.644 74.489 142.514 74.4846C142.385 74.4803 142.289 74.4718 142.226 74.4592C142.222 74.4801 142.209 74.4884 142.188 74.4842C142.071 74.5259 141.973 74.5279 141.893 74.4901C141.776 74.423 141.676 74.4355 141.592 74.5274C141.588 74.5483 141.575 74.5567 141.554 74.5525C141.533 74.5483 141.514 74.5336 141.498 74.5085C141.423 74.4498 141.347 74.4455 141.272 74.4956L141.278 74.4643ZM143.039 71.3914C143.081 71.3998 143.127 71.3873 143.177 71.3539C143.228 71.3205 143.259 71.2724 143.272 71.2097C143.28 71.1679 143.289 71.126 143.297 71.0842C143.31 71.0215 143.339 70.9838 143.385 70.9714L143.391 70.94L143.429 70.7518C143.438 70.7099 143.48 70.6096 143.555 70.4507L143.568 70.3879L143.517 70.4757C143.497 70.4715 143.482 70.4903 143.473 70.5322C143.469 70.5531 143.455 70.5719 143.429 70.5886C143.404 70.6053 143.381 70.6115 143.36 70.6073L143.323 70.6324L142.958 71.3097L142.983 71.3474L143.039 71.3914ZM143.574 70.0302C143.625 69.9968 143.635 69.9445 143.606 69.8734L143.581 69.8357L143.543 69.8608C143.556 69.9068 143.554 69.9716 143.537 70.0553L143.574 70.0302ZM143.738 69.7041L143.719 69.635C143.669 69.6685 143.644 69.6852 143.644 69.6852L143.638 69.7165L143.738 69.7041ZM143.788 69.6163C143.813 69.5996 143.832 69.5599 143.845 69.4971L143.757 69.61L143.788 69.6163ZM143.902 69.2148L143.877 69.1771L143.833 69.2335L143.82 69.2963L143.902 69.2148ZM144.053 69.1146C144.103 69.0812 144.13 69.054 144.134 69.0331C144.138 69.0122 144.13 68.9996 144.109 68.9954C144.088 68.9912 144.08 68.9786 144.084 68.9577L144.021 68.9451L144.04 69.0142L144.134 69.0331C144.084 69.0665 144.059 69.0832 144.059 69.0832L143.99 69.102L143.984 69.1333L144.053 69.1146ZM144.247 69.2843L144.379 69.115C144.358 69.1108 144.348 69.1087 144.348 69.1087C144.352 69.0878 144.354 69.0773 144.354 69.0773L144.348 69.1087L144.216 69.278L144.209 69.3093L144.247 69.2843ZM144.191 68.9139C144.195 68.893 144.197 68.8826 144.197 68.8826C144.218 68.8868 144.229 68.8889 144.229 68.8889L144.21 68.8198C144.172 68.7905 144.174 68.78 144.216 68.7885C144.22 68.7675 144.222 68.7571 144.222 68.7571C144.243 68.7613 144.254 68.7634 144.254 68.7634L144.336 68.6819L144.266 68.7007L144.235 68.6943C144.172 68.6817 144.137 68.6963 144.128 68.7381C144.128 68.7381 144.116 68.7465 144.091 68.7632C144.091 68.7632 144.101 68.7653 144.122 68.7695L144.191 68.9139ZM144.041 68.0351C144.062 68.0394 144.075 68.031 144.079 68.0101C144.104 67.9934 144.119 67.9746 144.123 67.9537C144.132 67.9118 144.148 67.8826 144.173 67.8659L144.18 67.8345L144.142 67.8596L144.048 68.0038L144.041 68.0351ZM144.619 68.0861L144.6 68.017L144.556 68.0735L144.575 68.1425L144.619 68.0861ZM144.832 68.3248C144.882 68.2914 144.909 68.2643 144.913 68.2434C144.918 68.2224 144.909 68.2099 144.888 68.2057L144.838 68.2935C144.817 68.2893 144.805 68.2976 144.8 68.3185C144.821 68.3227 144.832 68.3248 144.832 68.3248ZM144.795 67.8604C144.799 67.8395 144.822 67.8332 144.864 67.8416C144.843 67.8374 144.837 67.8144 144.845 67.7726C144.812 67.7223 144.795 67.6972 144.795 67.6972C144.774 67.693 144.761 67.7014 144.757 67.7223C144.728 67.7599 144.711 67.7892 144.707 67.8101C144.703 67.831 144.732 67.8478 144.795 67.8604ZM144.914 67.7538C144.918 67.7329 144.946 67.7058 144.996 67.6724L144.939 67.6284L144.87 67.6471C144.866 67.668 144.881 67.7036 144.914 67.7538ZM145.108 67.9235L145.115 67.8922L145.127 67.8294L145.058 67.8482L145.046 67.9109L145.039 67.9423L145.108 67.9235ZM145.31 67.0829C145.365 67.0285 145.405 66.993 145.43 66.9763L145.442 66.9136C145.451 66.8717 145.444 66.8487 145.424 66.8445L145.329 66.8256L145.317 66.8883C145.308 66.9301 145.327 66.9448 145.373 66.9323C145.377 66.9114 145.39 66.903 145.411 66.9073L145.405 66.9386C145.354 66.972 145.323 67.0201 145.31 67.0829ZM145.656 66.9892C145.66 66.9682 145.687 66.9411 145.737 66.9077C145.741 66.8868 145.733 66.8742 145.712 66.87C145.708 66.8909 145.681 66.9181 145.631 66.9515L145.656 66.9892ZM151.526 69.7705L151.57 69.7141L151.514 69.6701C151.493 69.6658 151.48 69.6742 151.476 69.6951C151.493 69.7202 151.489 69.7412 151.463 69.7579L151.495 69.7642L151.526 69.7705ZM145.205 70.8482L145.343 70.8107L146.078 70.5669L146.85 70.298C146.992 70.2396 147.107 70.2084 147.195 70.2043L147.516 70.0729C147.633 70.0312 147.813 69.9478 148.056 69.8226L148.627 69.5785C148.891 69.4575 149.067 69.395 149.154 69.3909C149.154 69.3909 149.205 69.3575 149.305 69.2907L149.676 69.0715C150.082 68.8921 150.335 68.769 150.436 68.7022C150.561 68.6187 150.672 68.554 150.768 68.5081C150.869 68.4413 150.957 68.3828 151.032 68.3327C151.078 68.3202 151.116 68.2952 151.145 68.2576C151.195 68.2241 151.254 68.2033 151.321 68.195C151.514 68.1032 151.65 68.0218 151.729 67.9508C152.169 67.6041 152.376 67.4391 152.351 67.4558L152.703 67.1676C152.82 67.0171 153.017 66.7956 153.294 66.5031C153.524 66.2231 153.682 65.9283 153.766 65.6188L153.955 65.004C154.039 64.5857 154.071 64.2113 154.05 63.8808L154.038 63.6172C154.025 63.5712 154.003 63.523 153.969 63.4728C153.936 63.4225 153.907 63.3514 153.882 63.2593C153.861 63.1463 153.784 62.9893 153.65 62.7883C153.491 62.604 153.383 62.4951 153.324 62.4616L153.261 62.4489C153.211 62.3736 153.128 62.3023 153.011 62.2352C152.898 62.1472 152.812 62.0865 152.753 62.0529C152.716 62.0236 152.593 61.9335 152.384 61.7826C152.363 61.7784 152.352 61.7763 152.352 61.7763C152.356 61.7554 152.358 61.7449 152.358 61.7449C152.413 61.6906 152.409 61.6571 152.346 61.6445L152.139 61.5375L151.851 61.3489C151.759 61.2651 151.675 61.2482 151.6 61.2984C151.436 61.4613 151.355 61.5428 151.355 61.5428L150.915 62.1071L150.431 62.7277C150.363 62.8448 150.242 63.0162 150.066 63.2419L149.657 63.8124C149.414 64.1552 149.242 64.4144 149.142 64.59L148.62 65.3989C148.523 65.5536 148.416 65.7061 148.299 65.8566C148.182 66.0071 148.075 66.1597 147.978 66.3143L147.595 66.9226C147.561 66.9811 147.513 67.0585 147.45 67.1546C147.392 67.2298 147.308 67.3218 147.199 67.4304C146.843 68.0115 146.633 68.3501 146.57 68.4463L145.954 69.3994L145.35 70.453C145.283 70.57 145.207 70.6745 145.124 70.7665C145.115 70.8083 145.121 70.8313 145.142 70.8355L145.205 70.8482ZM152.155 68.7546L152.161 68.7232L152.017 68.7921L152.042 68.8298L152.155 68.7546ZM152.425 68.5479C152.5 68.4978 152.538 68.4727 152.538 68.4727L152.4 68.5102C152.4 68.5102 152.398 68.5206 152.394 68.5415C152.394 68.5415 152.404 68.5437 152.425 68.5479ZM156.821 77.6586C156.716 77.6376 156.631 77.5768 156.564 77.4763L156.445 77.4197C156.298 77.3902 156.183 77.3127 156.1 77.187C156.02 77.1493 155.956 77.0927 155.906 77.0174C155.834 76.9378 155.736 76.8853 155.611 76.8601C155.586 76.8768 155.544 76.8684 155.485 76.8348C155.427 76.8013 155.377 76.7803 155.335 76.7719L154.965 76.5015C154.856 76.2839 154.716 76.1142 154.545 75.9927C154.432 75.9047 154.344 75.8544 154.282 75.8417C154.177 75.8207 154.116 75.7432 154.1 75.6093C154.071 75.5381 153.96 75.4397 153.768 75.3139C153.613 75.2175 153.461 75.0018 153.31 74.6669C153.281 74.5958 153.221 74.3551 153.129 73.945C153.113 73.8111 153.125 73.694 153.167 73.5936L153.136 73.5873L153.3 73.2612C153.375 73.1023 153.419 72.9915 153.432 72.9287L153.545 72.6904C153.595 72.657 153.639 72.6005 153.677 72.5211C153.715 72.4417 153.736 72.3915 153.74 72.3706C153.69 72.2952 153.68 72.2387 153.709 72.2011C153.763 72.1468 153.793 72.1091 153.797 72.0882C153.847 71.946 153.925 71.8311 154.03 71.7434C154.126 71.5887 154.229 71.4026 154.338 71.1852C154.38 71.0849 154.474 70.9406 154.621 70.7525C154.679 70.6773 154.857 70.4412 155.155 70.0441C155.26 69.8476 155.356 69.6929 155.444 69.58C155.537 69.4463 155.614 69.3313 155.677 69.2352C155.815 69.0889 155.949 68.9092 156.079 68.696C156.205 68.6124 156.285 68.487 156.318 68.3197L156.375 68.2006L156.513 67.9999C156.534 68.0041 156.557 67.9979 156.582 67.9812C156.607 67.9645 156.622 67.9457 156.626 67.9247L156.708 67.8433C156.943 67.5423 157.079 67.3521 157.117 67.2727C157.23 67.1431 157.33 67.0219 157.418 66.9091C157.51 66.7753 157.586 66.6708 157.645 66.5956L157.997 66.1442C158.03 66.0857 158.095 65.979 158.192 65.8244C158.288 65.6697 158.391 65.538 158.5 65.4294C158.642 65.2622 158.736 65.118 158.783 64.9967L159.072 64.5327C159.151 64.4617 159.208 64.3969 159.241 64.3384C159.279 64.2589 159.313 64.2004 159.342 64.1628C159.355 64.1 159.405 64.0122 159.493 63.8994C159.539 63.8869 159.556 63.8576 159.543 63.8116C159.556 63.7488 159.554 63.7049 159.537 63.6798L159.374 63.5164C159.379 63.4955 159.372 63.4725 159.356 63.4474C159.364 63.4055 159.381 63.3763 159.406 63.3596C159.427 63.255 159.421 63.1776 159.387 63.1273L159.4 63.0646L159.425 62.9391C159.413 62.7843 159.472 62.7091 159.601 62.7134C159.652 62.68 159.733 62.6529 159.846 62.6321C160.118 62.5781 160.355 62.4843 160.556 62.3506C160.597 62.359 160.625 62.3319 160.637 62.2691L161.034 61.5981C161.063 61.5605 161.071 61.5187 161.059 61.4727C161.067 61.4308 161.088 61.3807 161.122 61.3221C161.151 61.2845 161.197 61.2176 161.26 61.1215C161.348 61.0086 161.438 60.9397 161.53 60.9147C161.706 60.7978 161.909 60.7625 162.139 60.8088C162.348 60.8509 162.503 60.8929 162.603 60.9349C162.704 60.9769 162.796 61.0607 162.879 61.1863C162.938 61.2198 162.994 61.2638 163.048 61.3183C163.103 61.3728 163.159 61.4168 163.218 61.4503C163.23 61.4963 163.274 61.5487 163.349 61.6074C163.445 61.6702 163.512 61.7164 163.55 61.7457L163.788 62.0221C163.821 62.0724 163.87 62.1038 163.932 62.1164C164.154 62.0958 164.336 62.0563 164.478 61.9979C164.96 61.8772 165.412 61.7941 165.834 61.7486C166.161 61.6402 166.479 61.5737 166.788 61.549C167.081 61.4991 167.312 61.4911 167.479 61.5248L167.698 61.569L167.981 61.6258C168.002 61.63 168.052 61.651 168.131 61.6888C168.215 61.7056 168.271 61.7496 168.301 61.8208C168.317 61.8459 168.347 61.8627 168.388 61.8711C168.43 61.8795 168.47 61.8984 168.508 61.9277C168.524 61.9528 168.553 61.9696 168.595 61.978C168.616 61.9822 168.625 61.9948 168.62 62.0157L168.589 62.0094C168.568 62.0052 168.545 62.0114 168.52 62.0281C168.516 62.049 168.514 62.0595 168.514 62.0595L168.532 62.1286L168.495 62.1536L168.507 62.254L168.72 62.3296C168.72 62.3296 168.737 62.3547 168.77 62.405C168.787 62.4301 168.802 62.4657 168.814 62.5117C168.831 62.5369 168.843 62.5829 168.852 62.6499C168.839 62.7126 168.852 62.7586 168.889 62.788C168.927 62.8173 168.954 62.8445 168.971 62.8697C168.992 62.8739 169.012 62.9325 169.033 63.0455C169.071 63.0748 169.098 63.102 169.115 63.1271C169.152 63.1565 169.18 63.1837 169.196 63.2088C169.263 63.3093 169.265 63.4076 169.202 63.5038C169.177 63.6293 169.147 63.7213 169.114 63.7798L169.107 63.9744C169.111 64.0622 169.095 64.1459 169.057 64.2253L168.887 64.5828L168.749 64.7835L168.686 64.7708C168.652 64.7206 168.665 64.6578 168.724 64.5826C168.749 64.5659 168.766 64.5366 168.774 64.4948C168.787 64.4321 168.785 64.3881 168.768 64.363C168.756 64.317 168.743 64.2709 168.731 64.2249C168.718 64.1789 168.67 64.1474 168.586 64.1306C168.565 64.1264 168.551 64.1452 168.542 64.187L168.498 64.2434L168.511 64.1807C168.494 64.1556 168.492 64.1116 168.505 64.0489L168.317 64.011L168.222 63.9921C168.164 63.9585 168.08 63.9417 167.972 63.9415C167.653 64.0081 167.417 64.0475 167.262 64.0599C166.99 64.1139 166.584 64.1845 166.044 64.2717C165.601 64.313 165.277 64.3565 165.072 64.4023C164.959 64.423 164.789 64.4542 164.563 64.4957C164.341 64.5164 164.155 64.5224 164.005 64.5139C163.938 64.5221 163.858 64.5388 163.766 64.5638C163.699 64.572 163.62 64.5887 163.527 64.6137C163.394 64.6302 163.327 64.6385 163.327 64.6385C163.193 64.6551 163.084 64.6549 163 64.6381C162.975 64.6548 162.929 64.6673 162.862 64.6756C162.799 64.6629 162.766 64.6671 162.762 64.688L162.667 64.8322L162.29 65.4091C162.231 65.4843 162.146 65.5867 162.032 65.7163C161.944 65.8291 161.867 65.9441 161.8 66.0612C161.653 66.2492 161.546 66.4018 161.479 66.5189C161.391 66.6317 161.293 66.7425 161.184 66.8511C161.096 66.964 161.006 67.0873 160.913 67.221L160.788 67.3589L160.781 67.3903L160.844 67.4029L161.252 67.3219C161.382 67.3262 161.497 67.3494 161.597 67.3914C161.635 67.4207 161.758 67.4564 161.967 67.4985C162.03 67.5111 162.066 67.5509 162.074 67.6179C162.091 67.643 162.12 67.6598 162.162 67.6682C162.337 67.7688 162.446 67.8234 162.488 67.8318L162.475 67.8945L162.444 67.8882C162.423 67.884 162.41 67.8924 162.406 67.9133C162.402 67.9342 162.389 67.9425 162.369 67.9383C162.389 67.9425 162.398 67.9551 162.394 67.976C162.389 67.9969 162.398 68.0095 162.419 68.0137L162.632 68.0893L162.663 68.0956L162.77 68.215L162.632 68.2524C162.548 68.2356 162.494 68.2355 162.469 68.2522L162.437 68.2459C162.433 68.2668 162.441 68.2794 162.462 68.2836L162.55 68.3339L162.864 68.3971C162.906 68.4055 162.964 68.439 163.039 68.4977C163.06 68.6107 163.1 68.684 163.158 68.7175L163.34 68.7868C163.399 68.8203 163.424 68.858 163.415 68.8998C163.411 68.9208 163.399 68.9291 163.378 68.9249L163.139 68.8116L163.077 68.799C163.097 68.8032 163.106 68.8158 163.102 68.8367C163.11 68.9036 163.141 68.9643 163.196 69.0188C163.275 69.0566 163.334 69.0901 163.371 69.1194L163.603 69.4272C163.603 69.4272 163.601 69.4377 163.597 69.4586C163.597 69.4586 163.607 69.4607 163.628 69.4649L163.534 69.446C163.538 69.4251 163.53 69.4125 163.509 69.4083C163.488 69.4041 163.477 69.402 163.477 69.402C163.473 69.3141 163.457 69.289 163.427 69.3266C163.402 69.3433 163.379 69.3496 163.358 69.3453L163.364 69.4771L163.496 69.6342C163.496 69.6342 163.494 69.6447 163.49 69.6656C163.506 69.6907 163.525 69.7054 163.546 69.7096C163.504 69.7012 163.467 69.6718 163.433 69.6216L163.402 69.6153C163.402 69.6153 163.381 69.611 163.339 69.6026L163.352 69.703C163.51 69.7786 163.615 69.854 163.665 69.9294L163.778 70.1805L163.828 70.2559C163.865 70.2853 163.859 70.3166 163.809 70.35C163.784 70.3667 163.75 70.3709 163.708 70.3625L163.539 70.2304L163.276 70.0795C163.201 70.0208 163.173 70.048 163.194 70.161L163.188 70.1923L163.163 70.1547C163.15 70.1086 163.1 70.0876 163.012 70.0917L162.027 70.1218L161.104 70.1646L160.834 70.2082C160.504 70.2287 160.186 70.2408 159.88 70.2446C159.772 70.2445 159.661 70.2548 159.548 70.2756C159.439 70.2754 159.309 70.2711 159.159 70.2625C159.117 70.2541 159.039 70.2603 158.926 70.2811C158.818 70.2809 158.711 70.2703 158.606 70.2493L158.5 70.2931C158.336 70.5648 158.215 70.7362 158.135 70.8072L157.978 70.9388C157.802 71.1645 157.607 71.4299 157.393 71.7351C157.305 71.8479 157.213 71.9817 157.117 72.1364C157.045 72.2744 156.941 72.4165 156.802 72.5627C156.475 73.1062 156.274 73.4574 156.199 73.6163C156.161 73.6957 156.121 73.7856 156.079 73.886C156.041 73.9654 156.01 74.0679 155.984 74.1934C155.947 74.2728 155.972 74.3105 156.06 74.3064C156.131 74.2772 156.187 74.2669 156.229 74.2753C156.296 74.267 156.34 74.265 156.361 74.2692L156.392 74.2755C156.371 74.2713 156.359 74.2796 156.355 74.3005L156.009 74.3942C155.988 74.39 155.965 74.3963 155.94 74.413C155.94 74.413 155.93 74.4109 155.909 74.4067L156.034 74.4319L156.292 74.4511L156.354 74.4637L156.317 74.4888L156.015 74.526C155.948 74.5343 155.9 74.5573 155.871 74.5949C155.846 74.6116 155.837 74.6534 155.846 74.7204C155.841 74.7413 155.837 74.7622 155.833 74.7831C155.854 74.7873 155.862 74.7999 155.858 74.8208C155.85 74.8626 155.887 74.892 155.971 74.9088L156.228 74.9279C156.295 74.9197 156.373 74.9135 156.46 74.9094C156.573 74.8886 156.682 74.8888 156.787 74.9098L156.85 74.9225C156.87 74.9267 156.891 74.9309 156.912 74.9351C156.954 74.9435 156.983 74.9603 157 74.9854C157.067 75.0859 157.136 75.1216 157.207 75.0924L158.243 74.9744L158.682 74.8997L158.745 74.9123C158.787 74.9207 158.854 74.9125 158.946 74.8875C159.038 74.8625 159.128 74.848 159.216 74.8439C159.262 74.8314 159.331 74.8127 159.423 74.7877C159.54 74.746 159.653 74.7252 159.762 74.7253C159.783 74.7296 159.929 74.7046 160.201 74.6506C160.335 74.634 160.438 74.6111 160.509 74.5819C160.601 74.557 160.68 74.5403 160.747 74.532C160.919 74.5448 161.007 74.5407 161.011 74.5198L161.055 74.4634C161.076 74.4676 161.084 74.4802 161.08 74.5011C161.076 74.522 161.074 74.5325 161.074 74.5325C161.149 74.4823 161.178 74.4991 161.161 74.5828C161.178 74.6079 161.197 74.6226 161.218 74.6268C161.26 74.6352 161.283 74.629 161.287 74.608L161.318 74.6144L161.381 74.627L161.387 74.5956L161.4 74.5329C161.404 74.512 161.417 74.5036 161.438 74.5078L161.431 74.5392L161.412 74.6333C161.412 74.6333 161.387 74.65 161.337 74.6834L161.324 74.7462C161.32 74.7671 161.316 74.788 161.312 74.8089C161.333 74.8131 161.341 74.8257 161.337 74.8466C161.353 74.8717 161.408 74.9262 161.5 75.01C161.521 75.0142 161.529 75.0267 161.525 75.0476C161.575 75.2318 161.631 75.3302 161.694 75.3428C161.715 75.347 161.727 75.3387 161.732 75.3178C161.757 75.3011 161.78 75.2948 161.801 75.299L161.838 75.274C161.838 75.274 161.836 75.2844 161.832 75.3053C161.853 75.3095 161.874 75.3138 161.895 75.318L161.888 75.3493L161.863 75.4748C161.884 75.479 161.92 75.4644 161.97 75.431C162.02 75.3976 162.047 75.3705 162.052 75.3495C162.052 75.3495 162.054 75.3391 162.058 75.3182C162.083 75.3015 162.098 75.2827 162.102 75.2618C162.123 75.266 162.131 75.2785 162.127 75.2994C162.123 75.3204 162.131 75.3329 162.152 75.3371L162.146 75.3685C162.095 75.4019 162.074 75.4521 162.083 75.519C162.099 75.5442 162.101 75.5881 162.089 75.6508C162.11 75.7638 162.166 75.8078 162.258 75.7828C162.325 75.7746 162.377 75.7851 162.415 75.8144C162.461 75.9107 162.44 76.0153 162.352 76.1281C162.256 76.174 162.209 76.2409 162.213 76.3288C162.218 76.4166 162.217 76.471 162.213 76.4919L162.15 76.8056L162.112 76.8307C162.112 76.8307 162.102 76.8286 162.081 76.8244C162.06 76.8202 162.052 76.8076 162.056 76.7867C161.997 76.7531 161.964 76.7029 161.956 76.6359C161.943 76.5899 161.925 76.5752 161.899 76.5919C161.79 76.7006 161.627 76.7548 161.41 76.7545C161.297 76.7753 161.163 76.7918 161.008 76.8042C160.874 76.8208 160.728 76.8457 160.569 76.8789C160.435 76.8955 160.286 76.9309 160.123 76.9851L160.091 76.9787C160.054 76.9494 160.01 76.9514 159.96 76.9849C159.909 77.0183 159.874 77.0329 159.853 77.0286L159.815 77.0537L159.69 77.0284C159.656 77.087 159.606 77.1204 159.539 77.1287C159.472 77.1369 159.428 77.139 159.407 77.1348L159.213 77.1282C159.079 77.1448 158.968 77.2095 158.88 77.3224L158.848 77.3161C158.786 77.3034 158.698 77.3075 158.585 77.3283C158.472 77.349 158.382 77.3636 158.315 77.3719L158.039 77.4468C158.018 77.4426 157.982 77.4572 157.932 77.4906C157.869 77.478 157.838 77.4717 157.838 77.4717L157.775 77.459C157.712 77.4464 157.635 77.4526 157.543 77.4776C157.447 77.5235 157.365 77.5506 157.298 77.5588L157.154 77.6277L156.915 77.6776L156.821 77.6586ZM156.385 75.1227L156.46 75.0726L156.398 75.06C156.335 75.0473 156.289 75.0598 156.259 75.0974L156.222 75.1225L156.284 75.1351L156.385 75.1227ZM155.045 72.3722L155.102 72.2531C155.106 72.2321 155.098 72.2196 155.077 72.2154L155.071 72.2467C155.046 72.2634 155.027 72.3032 155.014 72.3659L155.045 72.3722ZM156.692 75.0541C156.797 75.0751 156.872 75.0794 156.918 75.0669L156.95 75.0732L156.925 75.0355L156.692 75.0541L156.661 75.0477C156.661 75.0477 156.659 75.0582 156.655 75.0791C156.676 75.0833 156.688 75.075 156.692 75.0541ZM155.297 71.9332C155.347 71.8998 155.379 71.8518 155.391 71.789L155.398 71.7577L155.366 71.7513L155.278 71.8642L155.266 71.9269L155.297 71.9332ZM158.994 76.105C159.024 76.0674 159.049 76.0507 159.07 76.0549C159.091 76.0591 159.114 76.0529 159.139 76.0362L159.515 75.9488C159.578 75.9614 159.656 75.9552 159.748 75.9303L159.792 75.8738L159.723 75.8926C159.505 75.8923 159.338 75.913 159.22 75.9547C159.17 75.9881 159.099 76.0173 159.007 76.0423C158.986 76.0381 158.971 76.0569 158.963 76.0987L158.994 76.105ZM159.114 75.509C159.252 75.4715 159.388 75.4445 159.522 75.4279C159.656 75.4114 159.769 75.3906 159.861 75.3656L159.93 75.3469C159.889 75.3384 159.868 75.3342 159.868 75.3342L159.435 75.3776C159.389 75.3901 159.33 75.4109 159.259 75.4401C159.213 75.4526 159.154 75.4735 159.083 75.5027L159.052 75.4964L159.083 75.5027L159.114 75.509ZM160.282 75.2218C160.437 75.2094 160.562 75.1803 160.659 75.1344L160.784 75.1597L160.634 75.0967C160.491 75.1551 160.376 75.1863 160.288 75.1904C160.288 75.1904 160.286 75.2009 160.282 75.2218C160.282 75.2218 160.272 75.2197 160.251 75.2155L160.282 75.2218ZM168.41 64.5195L168.423 64.4567C168.435 64.394 168.454 64.3543 168.479 64.3375L168.511 64.3439L168.435 64.5571L168.404 64.5508L168.41 64.5195ZM30.1863 76.6458C30.0817 76.6247 29.996 76.564 29.9292 76.4635L29.81 76.4068C29.6636 76.3774 29.5487 76.2998 29.4652 76.1742C29.3857 76.1364 29.3209 76.0799 29.2708 76.0045C29.1998 75.9249 29.1016 75.8725 28.9761 75.8472C28.951 75.8639 28.9091 75.8555 28.8506 75.822C28.7921 75.7884 28.7419 75.7675 28.7001 75.759L28.3301 75.4887C28.2216 75.271 28.0817 75.1014 27.9103 74.9798C27.7975 74.8918 27.7097 74.8415 27.6469 74.8289C27.5423 74.8078 27.4818 74.7304 27.4652 74.5965C27.436 74.5253 27.3253 74.4268 27.133 74.3011C26.9783 74.2046 26.8259 73.989 26.6757 73.6541C26.6465 73.5829 26.5861 73.3423 26.4946 72.9322C26.478 72.7982 26.4907 72.6811 26.5327 72.5808L26.5013 72.5744L26.6649 72.2483C26.7404 72.0894 26.7845 71.9786 26.7971 71.9159L26.9104 71.6775C26.9606 71.6441 27.0046 71.5877 27.0424 71.5083C27.0801 71.4288 27.1011 71.3786 27.1053 71.3577C27.0552 71.2823 27.0448 71.2259 27.0742 71.1882C27.1286 71.1339 27.158 71.0963 27.1622 71.0754C27.2126 70.9332 27.2901 70.8182 27.3948 70.7305C27.4912 70.5758 27.594 70.3898 27.703 70.1724C27.745 70.072 27.8393 69.9278 27.986 69.7397C28.0447 69.6645 28.2228 69.4283 28.5203 69.0312C28.6252 68.8347 28.7216 68.68 28.8096 68.5672C28.9018 68.4334 28.9794 68.3185 29.0422 68.2223C29.1805 68.0761 29.3146 67.8963 29.4446 67.6831C29.5702 67.5996 29.6499 67.4742 29.6835 67.3069L29.7402 67.1877L29.8785 66.9871C29.8994 66.9913 29.9224 66.985 29.9475 66.9683C29.9727 66.9516 29.9873 66.9328 29.9915 66.9119L30.0732 66.8304C30.3079 66.5295 30.4441 66.3393 30.4819 66.2599C30.595 66.1303 30.6956 66.0091 30.7836 65.8962C30.8758 65.7625 30.9512 65.658 31.0099 65.5827L31.3619 65.1313C31.3955 65.0728 31.4604 64.9662 31.5569 64.8115C31.6533 64.6568 31.756 64.5252 31.8649 64.4165C32.0073 64.2494 32.1017 64.1052 32.1478 63.9839L32.4371 63.5198C32.5167 63.4488 32.5733 63.384 32.6068 63.3255C32.6446 63.2461 32.6781 63.1875 32.7074 63.1499C32.7201 63.0872 32.7704 62.9994 32.8584 62.8865C32.9044 62.874 32.9212 62.8448 32.9087 62.7987C32.9213 62.736 32.9193 62.6921 32.9026 62.6669L32.7396 62.5036C32.7439 62.4826 32.7376 62.4596 32.7209 62.4345C32.7293 62.3927 32.7461 62.3634 32.7712 62.3467C32.7923 62.2421 32.7861 62.1647 32.7527 62.1145L32.7653 62.0517L32.7906 61.9263C32.7782 61.7714 32.8369 61.6962 32.9666 61.7006C33.0168 61.6672 33.0985 61.6401 33.2114 61.6193C33.4835 61.5652 33.72 61.4714 33.921 61.3378C33.9628 61.3462 33.99 61.319 34.0026 61.2563L34.3989 60.5853C34.4282 60.5477 34.4366 60.5059 34.4241 60.4598C34.4326 60.418 34.4535 60.3678 34.4871 60.3093C34.5164 60.2717 34.5625 60.2048 34.6254 60.1086C34.7134 59.9958 34.8034 59.9269 34.8955 59.9019C35.0714 59.785 35.2744 59.7497 35.5044 59.796C35.7135 59.8381 35.8683 59.8801 35.9686 59.9221C36.069 59.964 36.1609 60.0478 36.2445 60.1734C36.303 60.207 36.3594 60.251 36.4137 60.3055C36.4681 60.3599 36.5245 60.4039 36.583 60.4375C36.5955 60.4835 36.6394 60.5359 36.7146 60.5945C36.8107 60.6574 36.8776 60.7035 36.9152 60.7328L37.1534 61.0093C37.1868 61.0595 37.2349 61.091 37.2976 61.1036C37.5194 61.083 37.7014 61.0434 37.8437 60.9851C38.325 60.8643 38.777 60.7812 39.1996 60.7357C39.5261 60.6274 39.8441 60.5608 40.1538 60.5361C40.4467 60.4863 40.6768 60.4782 40.8441 60.5119L41.0637 60.5561L41.3461 60.613C41.367 60.6172 41.4172 60.6382 41.4966 60.6759C41.5803 60.6927 41.6367 60.7368 41.6659 60.8079C41.6826 60.833 41.7118 60.8498 41.7537 60.8582C41.7955 60.8667 41.8352 60.8855 41.8728 60.9149C41.8895 60.94 41.9188 60.9568 41.9606 60.9652C41.9815 60.9694 41.9899 60.982 41.9857 61.0029L41.9543 60.9966C41.9334 60.9923 41.9104 60.9986 41.8853 61.0153C41.8811 61.0362 41.8789 61.0467 41.8789 61.0467L41.8977 61.1157L41.86 61.1408L41.8724 61.2412L42.0857 61.3168C42.0857 61.3168 42.1024 61.3419 42.1358 61.3922C42.1525 61.4173 42.1671 61.4529 42.1796 61.4989C42.1963 61.524 42.2088 61.5701 42.2171 61.637C42.2045 61.6998 42.2169 61.7458 42.2546 61.7751C42.2922 61.8045 42.3193 61.8317 42.336 61.8568C42.357 61.861 42.3778 61.9196 42.3986 62.0326C42.4362 62.0619 42.4634 62.0892 42.4801 62.1143C42.5177 62.1436 42.5448 62.1709 42.5615 62.196C42.6284 62.2965 42.6303 62.3948 42.5674 62.491C42.5422 62.6164 42.5128 62.7084 42.4792 62.767L42.4727 62.9615C42.4768 63.0494 42.4599 63.133 42.4222 63.2125L42.2523 63.57L42.114 63.7706L42.0512 63.758C42.0178 63.7077 42.0304 63.645 42.0891 63.5698C42.1142 63.5531 42.131 63.5238 42.1394 63.482C42.1521 63.4192 42.15 63.3753 42.1333 63.3502C42.1208 63.3041 42.1083 63.2581 42.0958 63.2121C42.0834 63.166 42.0353 63.1346 41.9516 63.1177C41.9307 63.1135 41.916 63.1323 41.9076 63.1742L41.8636 63.2306L41.8762 63.1679C41.8595 63.1427 41.8575 63.0988 41.8701 63.0361L41.6819 62.9982L41.5878 62.9792C41.5293 62.9457 41.4456 62.9288 41.3368 62.9287C41.0188 62.9952 40.7824 63.0347 40.6275 63.047C40.3555 63.1011 39.9496 63.1717 39.4098 63.2589C38.9662 63.3001 38.6419 63.3436 38.4369 63.3894C38.3239 63.4102 38.1544 63.4413 37.9284 63.4829C37.7067 63.5035 37.5205 63.5096 37.3699 63.501C37.3029 63.5093 37.2234 63.5259 37.1313 63.5509C37.0644 63.5592 36.9849 63.5758 36.8928 63.6008C36.7589 63.6174 36.6919 63.6257 36.6919 63.6257C36.558 63.6422 36.4492 63.6421 36.3656 63.6253C36.3405 63.642 36.2944 63.6544 36.2275 63.6627C36.1647 63.6501 36.1313 63.6542 36.127 63.6752L36.0327 63.8194L35.6554 64.3963C35.5968 64.4715 35.5109 64.5739 35.3978 64.7034C35.3097 64.8163 35.2322 64.9313 35.1651 65.0483C35.0184 65.2364 34.9116 65.389 34.8445 65.506C34.7565 65.6189 34.658 65.7296 34.5491 65.8383C34.4611 65.9511 34.371 66.0744 34.2788 66.2082L34.1531 66.3461L34.1468 66.3775L34.2095 66.3901L34.6175 66.309C34.7472 66.3134 34.8622 66.3365 34.9626 66.3785C35.0002 66.4078 35.1236 66.4436 35.3327 66.4857C35.3955 66.4983 35.431 66.5381 35.4393 66.605C35.456 66.6302 35.4852 66.6469 35.5271 66.6554C35.7027 66.756 35.8114 66.8105 35.8532 66.8189L35.8406 66.8817L35.8092 66.8754C35.7883 66.8712 35.7757 66.8795 35.7715 66.9004C35.7673 66.9213 35.7547 66.9297 35.7338 66.9255C35.7547 66.9297 35.7631 66.9422 35.7589 66.9632C35.7547 66.9841 35.763 66.9966 35.7839 67.0009L35.9972 67.0764L36.0286 67.0827L36.1351 67.2021L35.997 67.2396C35.9133 67.2228 35.859 67.2227 35.8338 67.2394L35.8025 67.2331C35.7982 67.254 35.8066 67.2666 35.8275 67.2708L35.9153 67.3211L36.229 67.3842C36.2708 67.3927 36.3294 67.4262 36.4046 67.4849C36.4254 67.5979 36.465 67.6711 36.5236 67.7047L36.7055 67.7739C36.764 67.8075 36.7891 67.8452 36.7806 67.887C36.7764 67.9079 36.7639 67.9163 36.743 67.912L36.5046 67.7988L36.4419 67.7862C36.4628 67.7904 36.4711 67.8029 36.4669 67.8238C36.4752 67.8908 36.5065 67.9515 36.5608 68.006C36.6403 68.0437 36.6988 68.0773 36.7364 68.1066L36.9682 68.4144C36.9682 68.4144 36.9661 68.4248 36.9619 68.4458C36.9619 68.4458 36.9724 68.4479 36.9933 68.4521L36.8992 68.4331C36.9034 68.4122 36.895 68.3997 36.8741 68.3954C36.8532 68.3912 36.8428 68.3891 36.8428 68.3891C36.8387 68.3013 36.822 68.2761 36.7926 68.3138C36.7675 68.3305 36.7445 68.3367 36.7236 68.3325L36.7297 68.4643L36.8613 68.6214C36.8613 68.6214 36.8592 68.6318 36.855 68.6527C36.8717 68.6779 36.8905 68.6925 36.9114 68.6967C36.8696 68.6883 36.832 68.659 36.7985 68.6087L36.7672 68.6024C36.7672 68.6024 36.7463 68.5982 36.7044 68.5898L36.7169 68.6902C36.8758 68.7657 36.9803 68.8412 37.0304 68.9165L37.143 69.1677L37.1931 69.2431C37.2307 69.2724 37.2244 69.3038 37.1742 69.3372C37.149 69.3539 37.1156 69.358 37.0737 69.3496L36.9045 69.2176L36.6411 69.0667C36.5658 69.008 36.5386 69.0351 36.5594 69.1481L36.5531 69.1795L36.528 69.1418C36.5155 69.0958 36.4653 69.0748 36.3775 69.0789L35.3922 69.109L34.4696 69.1518L34.1997 69.1953C33.8691 69.2158 33.5511 69.228 33.2457 69.2318C33.1369 69.2316 33.026 69.242 32.913 69.2627C32.8043 69.2626 32.6746 69.2582 32.524 69.2497C32.4821 69.2413 32.4047 69.2474 32.2917 69.2682C32.183 69.2681 32.0763 69.2575 31.9717 69.2364L31.865 69.2802C31.7015 69.552 31.5799 69.7234 31.5003 69.7944L31.3433 69.926C31.1673 70.1517 30.9724 70.4171 30.7586 70.7222C30.6706 70.8351 30.5784 70.9689 30.482 71.1235C30.4107 71.2615 30.3059 71.4036 30.1676 71.5499C29.8406 72.0934 29.6394 72.4446 29.5638 72.6034C29.5261 72.6829 29.4862 72.7728 29.4443 72.8731C29.4065 72.9526 29.375 73.0551 29.3497 73.1805C29.312 73.26 29.337 73.2977 29.4249 73.2936C29.4961 73.2644 29.5526 73.254 29.5944 73.2624C29.6613 73.2541 29.7053 73.2521 29.7262 73.2563L29.7576 73.2626C29.7366 73.2584 29.7241 73.2668 29.7199 73.2877L29.3746 73.3814C29.3537 73.3772 29.3306 73.3834 29.3055 73.4001C29.3055 73.4001 29.2951 73.398 29.2742 73.3938L29.3996 73.4191L29.6569 73.4382L29.7197 73.4509L29.682 73.4759L29.3807 73.5132C29.3137 73.5215 29.2656 73.5444 29.2363 73.582C29.2111 73.5987 29.2027 73.6406 29.211 73.7075C29.2068 73.7284 29.2026 73.7493 29.1984 73.7703C29.2193 73.7745 29.2276 73.787 29.2234 73.8079C29.215 73.8498 29.2526 73.8791 29.3363 73.8959L29.5936 73.9151C29.6605 73.9068 29.7379 73.9006 29.8258 73.8966C29.9388 73.8758 30.0475 73.8759 30.1521 73.897L30.2149 73.9096C30.2358 73.9138 30.2567 73.918 30.2776 73.9222C30.3194 73.9307 30.3487 73.9474 30.3654 73.9726C30.4322 74.0731 30.5012 74.1087 30.5724 74.0795L31.608 73.9616L32.0474 73.8868L32.1101 73.8995C32.152 73.9079 32.2189 73.8996 32.311 73.8746C32.4031 73.8496 32.493 73.8351 32.5809 73.831C32.6269 73.8185 32.696 73.7998 32.7881 73.7748C32.9053 73.7331 33.0183 73.7124 33.127 73.7125C33.148 73.7167 33.2944 73.6918 33.5664 73.6377C33.7003 73.6212 33.8029 73.5983 33.874 73.5691C33.9661 73.5441 34.0456 73.5275 34.1126 73.5192C34.2841 73.532 34.372 73.5279 34.3762 73.507L34.4202 73.4506C34.4411 73.4548 34.4494 73.4673 34.4452 73.4882C34.441 73.5092 34.4389 73.5196 34.4389 73.5196C34.5143 73.4695 34.5435 73.4863 34.5267 73.5699C34.5434 73.5951 34.5622 73.6097 34.5831 73.6139C34.625 73.6224 34.648 73.6161 34.6522 73.5952L34.6836 73.6015L34.7463 73.6141L34.7526 73.5828L34.7652 73.52C34.7695 73.4991 34.782 73.4908 34.8029 73.495L34.7966 73.5263L34.7777 73.6205C34.7777 73.6205 34.7525 73.6372 34.7023 73.6706L34.6897 73.7333C34.6855 73.7542 34.6812 73.7751 34.677 73.796C34.698 73.8003 34.7063 73.8128 34.7021 73.8337C34.7188 73.8589 34.7731 73.9133 34.8651 73.9971C34.886 74.0013 34.8943 74.0139 34.8901 74.0348C34.9401 74.2189 34.9964 74.3173 35.0592 74.33C35.0801 74.3342 35.0927 74.3258 35.0969 74.3049C35.122 74.2882 35.145 74.282 35.1659 74.2862L35.2036 74.2611C35.2036 74.2611 35.2015 74.2716 35.1973 74.2925C35.2182 74.2967 35.2391 74.3009 35.26 74.3051L35.2537 74.3365L35.2285 74.462C35.2494 74.4662 35.285 74.4516 35.3352 74.4182C35.3854 74.3848 35.4127 74.3576 35.4169 74.3367C35.4169 74.3367 35.419 74.3262 35.4232 74.3053C35.4483 74.2886 35.463 74.2698 35.4672 74.2489C35.4881 74.2531 35.4965 74.2657 35.4923 74.2866C35.488 74.3075 35.4964 74.3201 35.5173 74.3243L35.511 74.3556C35.4607 74.3891 35.4398 74.4392 35.448 74.5062C35.4648 74.5313 35.4668 74.5752 35.4542 74.638C35.4749 74.751 35.5314 74.795 35.6234 74.77C35.6904 74.7617 35.7427 74.7722 35.7803 74.8016C35.8262 74.8979 35.8051 75.0024 35.7171 75.1153C35.6208 75.1612 35.5747 75.2281 35.5788 75.3159C35.5829 75.4038 35.5828 75.4582 35.5786 75.4791L35.5154 75.7928L35.4778 75.8179C35.4778 75.8179 35.4673 75.8157 35.4464 75.8115C35.4255 75.8073 35.4171 75.7948 35.4213 75.7738C35.3628 75.7403 35.3294 75.6901 35.3211 75.6231C35.3086 75.5771 35.2898 75.5624 35.2647 75.5791C35.1558 75.6877 34.9925 75.7419 34.775 75.7416C34.662 75.7624 34.5281 75.779 34.3733 75.7913C34.2394 75.8079 34.0929 75.8328 33.9339 75.8661C33.8 75.8827 33.6514 75.918 33.4882 75.9722L33.4568 75.9659C33.4192 75.9366 33.3752 75.9386 33.325 75.972C33.2747 76.0054 33.2392 76.02 33.2182 76.0158L33.1806 76.0409L33.0551 76.0156C33.0215 76.0741 32.9713 76.1075 32.9043 76.1158C32.8374 76.1241 32.7935 76.1261 32.7725 76.1219L32.578 76.1154C32.4441 76.132 32.3331 76.1967 32.2451 76.3095L32.2138 76.3032C32.151 76.2906 32.0632 76.2946 31.9502 76.3154C31.8372 76.3362 31.7472 76.3507 31.6803 76.359L31.404 76.434C31.3831 76.4298 31.3475 76.4444 31.2973 76.4778C31.2345 76.4651 31.2032 76.4588 31.2032 76.4588L31.1404 76.4462C31.0777 76.4336 31.0003 76.4397 30.9082 76.4647C30.8119 76.5106 30.7303 76.5377 30.6634 76.546L30.5189 76.6148L30.2804 76.6647L30.1863 76.6458ZM29.7502 74.1098L29.8256 74.0597L29.7628 74.0471C29.7001 74.0345 29.654 74.047 29.6247 74.0846L29.587 74.1096L29.6498 74.1223L29.7502 74.1098ZM28.4107 71.3594L28.4673 71.2402C28.4715 71.2193 28.4632 71.2067 28.4423 71.2025L28.436 71.2339C28.4108 71.2506 28.3919 71.2903 28.3793 71.3531L28.4107 71.3594ZM30.0578 74.0412C30.1624 74.0623 30.2377 74.0665 30.2837 74.054L30.3151 74.0604L30.29 74.0227L30.0578 74.0412L30.0264 74.0349C30.0264 74.0349 30.0243 74.0453 30.0201 74.0663C30.041 74.0705 30.0536 74.0621 30.0578 74.0412ZM28.6623 70.9204C28.7125 70.887 28.744 70.8389 28.7566 70.7762L28.7629 70.7448L28.7315 70.7385L28.6435 70.8513L28.6309 70.9141L28.6623 70.9204ZM32.3596 75.0922C32.389 75.0546 32.4141 75.0379 32.435 75.0421C32.4559 75.0463 32.479 75.04 32.5041 75.0233L32.8807 74.9359C32.9435 74.9486 33.0209 74.9424 33.113 74.9174L33.157 74.861L33.0879 74.8797C32.8703 74.8795 32.703 74.9002 32.5858 74.9418C32.5355 74.9753 32.4644 75.0045 32.3723 75.0294C32.3514 75.0252 32.3367 75.044 32.3283 75.0859L32.3596 75.0922ZM32.4796 74.4961C32.6178 74.4587 32.7538 74.4316 32.8877 74.4151C33.0216 74.3985 33.1346 74.3777 33.2266 74.3527L33.2957 74.334C33.2539 74.3256 33.233 74.3214 33.233 74.3214L32.7999 74.3648C32.7538 74.3772 32.6952 74.3981 32.6241 74.4273C32.578 74.4398 32.5194 74.4606 32.4483 74.4898L32.4169 74.4835L32.4483 74.4898L32.4796 74.4961ZM33.6473 74.2089C33.8021 74.1966 33.9277 74.1675 34.0239 74.1216L34.1494 74.1468L33.9989 74.0839C33.8566 74.1423 33.7415 74.1735 33.6536 74.1776C33.6536 74.1776 33.6515 74.188 33.6473 74.2089C33.6473 74.2089 33.6368 74.2068 33.6159 74.2026L33.6473 74.2089ZM41.7754 63.5066L41.788 63.4439C41.8007 63.3811 41.8195 63.3414 41.8447 63.3247L41.876 63.331L41.8005 63.5443L41.7691 63.538L41.7754 63.5066ZM38.1296 79.2242C38.0962 79.174 38.021 79.1153 37.9039 79.0482C37.8746 79.0858 37.8432 79.0795 37.8098 79.0293C37.6718 78.958 37.6008 78.8784 37.5967 78.7905L37.5405 78.5834L37.503 78.4452L37.5157 78.3825C37.5241 78.3407 37.52 78.3072 37.5033 78.2821L37.4719 78.2758C37.4761 78.2548 37.4657 78.1984 37.4407 78.1063C37.4449 78.0854 37.4408 78.0519 37.4283 78.0058C37.4325 77.9849 37.4514 77.9452 37.4849 77.8867C37.5101 77.87 37.5122 77.8051 37.4915 77.6921C37.479 77.6461 37.4476 77.6398 37.3973 77.6732L37.391 77.7046C37.3701 77.7004 37.3618 77.6878 37.366 77.6669C37.3912 77.5414 37.3997 77.4452 37.3914 77.3782C37.3957 77.3573 37.3811 77.3217 37.3476 77.2715L37.3603 77.2087L37.3853 77.2464L37.4167 77.2527C37.4293 77.19 37.4252 77.1565 37.4043 77.1523C37.3834 77.1481 37.375 77.1355 37.3792 77.1146C37.3919 77.0519 37.4107 77.0122 37.4359 76.9955C37.4401 76.9746 37.4464 76.9432 37.4548 76.9014L37.4611 76.87L37.4234 76.895L37.4108 76.9578L37.3794 76.9515C37.3627 76.9263 37.3607 76.8824 37.3733 76.8197C37.3608 76.7736 37.3671 76.7423 37.3923 76.7256C37.3965 76.7046 37.4007 76.6837 37.4049 76.6628L37.4363 76.6691C37.4865 76.6357 37.5137 76.6086 37.518 76.5877C37.5222 76.5667 37.5076 76.5312 37.4742 76.4809C37.4617 76.4349 37.4638 76.37 37.4807 76.2864C37.4975 76.2027 37.5374 76.1128 37.6003 76.0167C37.6422 75.9163 37.6674 75.8452 37.6759 75.8034C37.7052 75.7658 37.7366 75.7177 37.7702 75.6592C37.8037 75.6006 37.8477 75.5442 37.9022 75.4899C37.9693 75.3728 38.0049 75.3038 38.0091 75.2829L38.0154 75.2516C38.0154 75.2516 38.005 75.2494 37.9841 75.2452C37.9841 75.2452 37.982 75.2557 37.9778 75.2766L37.8394 75.4773C37.7808 75.5525 37.7472 75.611 37.7388 75.6528L37.6697 75.6716L37.6824 75.6088C37.6908 75.567 37.7243 75.5085 37.783 75.4333C37.7956 75.3705 37.8313 75.3015 37.89 75.2263C37.9277 75.1468 37.9634 75.0779 37.9969 75.0193C38.0305 74.9608 38.064 74.9023 38.0975 74.8437L38.2485 74.5803C38.2694 74.5846 38.2694 74.5846 38.2485 74.5803C38.2527 74.5594 38.2548 74.549 38.2548 74.549L38.2674 74.4862C38.2759 74.4444 38.3094 74.3859 38.3681 74.3106L38.3744 74.2793L38.343 74.273L38.299 74.3294L38.2613 74.3544L38.2676 74.3231C38.2676 74.3231 38.2572 74.321 38.2363 74.3168C38.2363 74.3168 38.2384 74.3063 38.2426 74.2854L38.2363 74.3168L38.1043 74.486L38.0666 74.5111L38.0729 74.4797C38.0897 74.3961 38.1128 74.3354 38.1422 74.2978C38.1548 74.2351 38.1737 74.1953 38.1988 74.1786C38.2281 74.141 38.2575 74.1034 38.2868 74.0658L38.3247 73.8776L38.2933 73.8712C38.2724 73.867 38.2599 73.8754 38.2556 73.8963L38.1866 73.915C38.1866 73.915 38.1761 73.9129 38.1552 73.9087C38.1594 73.8878 38.172 73.8795 38.1929 73.8837C38.2097 73.8 38.2412 73.7519 38.2872 73.7395L38.2935 73.7081C38.3313 73.6286 38.3816 73.5408 38.4445 73.4447C38.5074 73.3485 38.5535 73.2817 38.5828 73.244C38.6415 73.1688 38.675 73.1103 38.6834 73.0685C38.7086 73.0517 38.7107 73.0413 38.6898 73.0371C38.694 73.0162 38.6982 72.9953 38.7024 72.9743C38.6606 72.9659 38.6375 72.9722 38.6333 72.9931C38.6333 72.9931 38.6082 73.0098 38.558 73.0432L38.5769 72.9491L38.6649 72.8362L38.6712 72.8049L38.6399 72.7985C38.6314 72.8404 38.6021 72.878 38.5519 72.9114L38.5455 72.9428C38.5497 72.9218 38.5414 72.9093 38.5205 72.9051L38.5771 72.7859L38.5834 72.7545C38.5625 72.7503 38.55 72.7587 38.5457 72.7796C38.4955 72.813 38.4641 72.8611 38.4514 72.9238C38.4305 72.9196 38.4179 72.928 38.4137 72.9489L38.4765 72.9615C38.4765 72.9615 38.4744 72.972 38.4702 72.9929C38.4702 72.9929 38.4806 72.995 38.5015 72.9992C38.4806 72.995 38.4681 73.0033 38.4638 73.0242C38.4053 72.9907 38.3676 73.0158 38.3508 73.0994L38.0177 73.4567L38.024 73.4253L38.1687 73.1933C38.2902 73.0219 38.4013 72.8484 38.5019 72.6729L38.7786 72.2716L38.8226 72.2151C38.7808 72.2067 38.7577 72.213 38.7535 72.2339L38.6215 72.4031L38.5775 72.4596C38.5859 72.4177 38.6006 72.3989 38.6215 72.4031L39.0365 71.8012C39.179 71.634 39.3759 71.3582 39.6275 70.9736L39.9418 70.5472C40.034 70.4134 40.1388 70.2713 40.2561 70.1209C40.3777 69.9495 40.4909 69.7655 40.5957 69.569C40.6419 69.4478 40.6943 69.3495 40.753 69.2743C40.8116 69.199 40.8578 69.1322 40.8913 69.0736C41.0757 68.8061 41.2036 68.6033 41.2749 68.4654L41.7151 67.7379L42.0484 67.2175C42.1826 66.9834 42.2727 66.8057 42.3189 66.6844L42.4446 66.5465C42.6333 66.258 42.7821 66.0051 42.8912 65.7877C42.9289 65.7082 43.0065 65.5933 43.1238 65.4428L43.5832 64.4581L43.8975 64.0318L44.0485 63.7684L44.1805 63.5991L44.2558 63.549C44.2685 63.4862 44.3083 63.3963 44.3754 63.2793L44.6205 63.0348C44.6456 63.0181 44.6624 62.9889 44.6708 62.947C44.721 62.9136 44.7566 62.899 44.7775 62.9033C44.8403 62.9159 44.9177 62.9097 45.0098 62.8847L45.0161 62.8533C45.0496 62.7948 45.0769 62.7133 45.098 62.6087C45.1106 62.546 45.1734 62.5042 45.2864 62.4834C45.3282 62.4918 45.3617 62.4877 45.3868 62.471C45.412 62.4543 45.4371 62.4376 45.4622 62.4209C45.4664 62.4 45.4936 62.3728 45.5439 62.3394C45.5481 62.3185 45.5607 62.3101 45.5816 62.3144L45.6005 62.2202L45.6696 62.2015L45.6319 62.2266L45.6506 62.2956C45.6715 62.2998 45.682 62.3019 45.682 62.3019C45.6862 62.281 45.6883 62.2706 45.6883 62.2706C45.7301 62.279 45.749 62.2937 45.7447 62.3146L45.7761 62.3209L45.8075 62.3272L45.8012 62.3586L45.6755 62.4965L45.6565 62.5906L45.7005 62.5342C45.7047 62.5132 45.7633 62.4924 45.8763 62.4716C45.8973 62.4758 45.9391 62.4843 46.0018 62.4969C46.0897 62.4928 46.1608 62.4636 46.2153 62.4093L46.253 62.3842L46.2717 62.4533C46.2633 62.4951 46.2675 62.5286 46.2842 62.5537C46.3344 62.5203 46.3595 62.5036 46.3595 62.5036C46.3847 62.4869 46.4789 62.3971 46.6423 62.2341C46.7344 62.2091 46.7951 62.1778 46.8244 62.1402C46.8244 62.1402 46.8348 62.1423 46.8558 62.1465C46.8767 62.1507 46.885 62.1633 46.8808 62.1842C46.8891 62.2512 46.9393 62.2722 47.0314 62.2472C47.0356 62.2263 47.0481 62.2179 47.069 62.2221L47.025 62.2785C47.0208 62.2995 47.0062 62.3183 46.981 62.335C46.9559 62.3517 46.9517 62.3726 46.9684 62.3977C46.9851 62.4228 47.0248 62.4417 47.0876 62.4543C47.1712 62.4712 47.211 62.4357 47.2069 62.3478C47.2154 62.306 47.2405 62.2893 47.2823 62.2977C47.3451 62.3103 47.4016 62.2999 47.4518 62.2665C47.4978 62.254 47.5522 62.2541 47.615 62.2667C47.6777 62.2794 47.7279 62.3003 47.7655 62.3297C47.7655 62.3297 47.7822 62.3548 47.8156 62.4051C47.8281 62.4511 47.8071 62.5013 47.7527 62.5556C47.7233 62.5932 47.7066 62.6225 47.7024 62.6434C47.6939 62.6852 47.7002 62.7082 47.7211 62.7124L47.7148 62.7438L47.5703 62.8127L47.5577 62.8754C47.6454 62.9801 47.6662 63.1475 47.6198 63.3775L47.5693 63.6285C47.5356 63.7958 47.4475 64.0174 47.3049 64.2934C47.2545 64.4356 47.1998 64.6531 47.1409 64.9459L47.103 65.1341C47.0525 65.3851 47.0291 65.6632 47.0329 65.9687C47.0453 66.1235 47.0387 66.3724 47.0131 66.7155C47.0172 66.8033 47.0004 66.887 46.9626 66.9664C46.9458 67.0501 46.9394 67.1358 46.9434 67.2237C46.9224 67.3283 46.9117 67.4893 46.9115 67.7069C46.8734 68.0039 46.852 68.3804 46.8473 68.8364L46.8022 69.7087L46.7637 70.3864C46.7466 70.6877 46.7212 70.9219 46.6875 71.0892C46.662 71.4323 46.6324 71.6874 46.5987 71.8547C46.5945 71.8757 46.6028 71.8882 46.6237 71.8924C46.5985 72.0179 46.5857 72.1894 46.5854 72.407L46.6166 72.5765C46.6458 72.6476 46.6539 72.8234 46.641 73.1037C46.6326 73.1455 46.62 73.2082 46.6031 73.2919C46.6114 73.3588 46.5883 73.4195 46.5339 73.4738L46.5526 73.5429L46.6217 73.5241L46.8543 73.1792L47.1686 72.7529L47.4263 72.4457L47.6023 72.22L47.8914 71.9191L48.1114 71.637L48.256 71.405C48.2854 71.3674 48.3608 71.2629 48.4824 71.0915L48.891 70.5209C48.9245 70.4624 48.956 70.4143 48.9853 70.3767C49.0189 70.3182 49.0503 70.2701 49.0796 70.2325L49.262 69.9754L49.7209 69.317L49.9222 68.9659L50.3308 68.3953L50.6955 67.8811L51.1168 67.2478L51.6951 66.4829C51.758 66.3868 51.8188 66.3011 51.8774 66.2259C51.957 66.1548 52.0136 66.0901 52.0471 66.0315C52.1603 65.902 52.309 65.7034 52.4935 65.4359L52.9021 64.8653L53.0152 64.7902L52.9648 64.878L52.7259 65.2542L52.6819 65.3106C52.6107 65.3398 52.5374 65.4339 52.4619 65.5928C52.4577 65.6137 52.4262 65.6617 52.3676 65.737C52.3298 65.8164 52.2523 65.9314 52.1349 66.0818C52.0762 66.1571 52.0218 66.2114 51.9715 66.2448C51.9715 66.2448 51.9694 66.2553 51.9652 66.2762C51.9652 66.2762 51.9757 66.2783 51.9966 66.2825L52.028 66.2888L52.1349 66.0818L52.1097 66.2073L52.0907 66.3014C52.0656 66.3181 52.0509 66.3369 52.0467 66.3579C52.0634 66.383 52.0948 66.3893 52.1408 66.3768C52.1869 66.3643 52.2036 66.3894 52.1909 66.4522C52.1742 66.4271 52.1533 66.4228 52.1282 66.4396C52.1031 66.4563 52.0905 66.4646 52.0905 66.4646L52.0779 66.5273L52.1029 66.565C52.1783 66.5149 52.2076 66.4773 52.1909 66.4522C52.283 66.4272 52.327 66.3708 52.3229 66.2829C52.3229 66.2829 52.3146 66.2703 52.2979 66.2452C52.3063 66.2034 52.3314 66.1867 52.3733 66.1951C52.3859 66.1324 52.4131 66.1052 52.4549 66.1136C52.4759 66.1178 52.4905 66.099 52.4989 66.0572C52.4655 66.007 52.4802 65.9881 52.5429 66.0008L52.5493 65.9694C52.5326 65.9443 52.5242 65.9317 52.5242 65.9317C52.5493 65.915 52.564 65.8962 52.5682 65.8753L52.7632 65.5555L52.8952 65.3862C52.9203 65.3695 52.9769 65.3047 53.0649 65.1919L53.1089 65.1354L53.1967 65.1858L53.228 65.1921C53.2531 65.1754 53.2574 65.1545 53.2407 65.1293L53.2093 65.123L53.1089 65.1354L53.2032 64.9912L53.2722 64.9725L53.3036 64.9788C53.3161 65.0248 53.3475 65.0312 53.3977 64.9977L53.5234 64.8598C53.5318 64.818 53.5465 64.7992 53.5674 64.8034L53.6114 64.747L53.5988 64.8097L53.4038 65.1295L53.3598 65.186C53.3096 65.2194 53.2928 65.2486 53.3095 65.2738C53.2844 65.2905 53.2676 65.3197 53.2592 65.3616C53.2759 65.3867 53.2717 65.4076 53.2466 65.4243L53.2402 65.4557C53.2402 65.4557 53.2298 65.4536 53.2089 65.4494C53.2089 65.4494 53.211 65.4389 53.2152 65.418L53.2215 65.3866L53.2278 65.3552L53.2215 65.3866L53.1335 65.4995C53.0833 65.5329 53.0874 65.5664 53.1459 65.5999L53.1333 65.6626C53.0746 65.7379 53.039 65.8069 53.0263 65.8696C53.0263 65.8696 53.0117 65.8884 52.9823 65.926C52.9781 65.9469 52.9969 65.9616 53.0388 65.97L53.0198 66.0641C52.9989 66.0599 52.9863 66.0683 52.9821 66.0892L53.0449 66.1018L53.1706 65.9639C53.2501 65.8929 53.3528 65.7612 53.4786 65.5689L53.6232 65.3369C53.6274 65.316 53.6295 65.3056 53.6295 65.3056C53.6504 65.3098 53.6609 65.3119 53.6609 65.3119L53.6546 65.3432C53.5415 65.4728 53.4597 65.6087 53.4093 65.7509L53.403 65.7822C53.4239 65.7864 53.4365 65.7781 53.4407 65.7572L53.6293 65.4687C53.6587 65.4311 53.7299 65.3475 53.843 65.218C53.8472 65.1971 53.8493 65.1866 53.8493 65.1866C53.8745 65.1699 53.8787 65.149 53.862 65.1239C53.8662 65.1029 53.8787 65.0946 53.8996 65.0988C53.9248 65.0821 53.9415 65.0528 53.95 65.011L53.975 65.0487C53.9499 65.0654 53.9352 65.0842 53.931 65.1051C53.9477 65.1302 53.9435 65.1512 53.9184 65.1679C53.8933 65.1846 53.8681 65.2557 53.8428 65.3811L53.9119 65.3624L54.0502 65.1617C54.1004 65.1283 54.1465 65.1158 54.1883 65.1243L54.2574 65.1055L54.3014 65.0491L54.2637 65.0742L54.1946 65.0929C54.203 65.0511 54.2177 65.0323 54.2386 65.0365C54.2428 65.0156 54.2701 64.9884 54.3203 64.955L54.3517 64.9613L54.446 64.8171C54.4669 64.8213 54.4774 64.8234 54.4774 64.8234C54.4816 64.8025 54.4837 64.792 54.4837 64.792C54.5673 64.8089 54.6218 64.7546 54.6471 64.6291C54.6513 64.6082 54.6638 64.5998 54.6847 64.604C54.7308 64.5915 54.7621 64.5978 54.7789 64.623C54.8541 64.6816 54.9147 64.7047 54.9608 64.6922L55.0235 64.7049C55.0193 64.7258 55.0067 64.7341 54.9858 64.7299L54.678 64.9617L54.4517 65.2752C54.4308 65.271 54.4182 65.2794 54.414 65.3003C54.4349 65.3045 54.4475 65.2961 54.4517 65.2752C54.4977 65.2627 54.5501 65.2189 54.6087 65.1436L54.7344 65.0057C54.7722 64.9263 54.8601 64.8678 54.9982 64.8303C55.0443 64.8178 55.0966 64.774 55.1553 64.6987L55.2684 64.6236L55.3311 64.6362L55.3122 64.7303L55.2745 64.7554L55.3058 64.7617C55.3477 64.7701 55.3728 64.7534 55.3812 64.7116C55.3645 64.6865 55.3666 64.676 55.3875 64.6802C55.4126 64.6635 55.4357 64.6573 55.4566 64.6615C55.5193 64.6741 55.5821 64.6324 55.645 64.5362C55.645 64.5362 55.7455 64.4694 55.9465 64.3358L55.9402 64.3671L55.7705 64.5615C55.7369 64.62 55.7243 64.6827 55.7326 64.7497C55.766 64.7999 55.7932 64.8272 55.8141 64.8314C55.8768 64.844 55.8831 64.867 55.8328 64.9004L55.7511 64.9819C55.5501 65.1155 55.3721 65.2973 55.217 65.5272C54.9781 65.8491 54.7811 66.1793 54.6258 66.518C54.5629 66.6142 54.498 66.7208 54.4309 66.8378C54.3847 66.9591 54.3302 67.0678 54.2673 67.164C54.1289 67.419 53.9528 67.6991 53.7391 68.0043C53.6678 68.1422 53.5399 68.345 53.3555 68.6125C53.3219 68.671 53.2569 68.7776 53.1605 68.9323C53.0892 69.0703 52.9991 69.1936 52.8902 69.3022L52.8272 69.4528L52.387 70.1802L52.0788 70.7384C51.9111 71.031 51.7979 71.215 51.7392 71.2902C51.693 71.4115 51.6134 71.5369 51.5002 71.6664C51.3703 71.8796 51.2068 72.097 51.0099 72.3185C50.926 72.5192 50.8547 72.6572 50.796 72.7324L50.752 72.7888L50.5634 73.0773L50.1922 73.786L49.884 74.3441C49.8504 74.4026 49.819 74.4507 49.7897 74.4883C49.7645 74.505 49.7394 74.5217 49.7143 74.5384C49.7059 74.5803 49.6891 74.6095 49.664 74.6262C49.6598 74.6472 49.6283 74.6952 49.5697 74.7705C49.3559 75.0756 49.1946 75.2825 49.0856 75.3911L48.9536 75.5604C48.9452 75.6022 48.9305 75.6211 48.9096 75.6168L48.4633 76.2125C48.2748 76.3921 48.1469 76.5949 48.0797 76.8207L47.8974 77.0778L47.6018 77.5732C47.518 77.6651 47.4426 77.7696 47.3755 77.8867C47.3335 77.9871 47.2832 78.0749 47.2245 78.1501C47.1701 78.2044 47.126 78.3152 47.0923 78.4825C47.0755 78.5662 47.1068 78.6269 47.1862 78.6647C47.2447 78.6982 47.2698 78.7359 47.2614 78.7777C47.2739 78.8237 47.2654 78.8656 47.2361 78.9032L47.0852 79.1666L47.0033 79.4112C46.9864 79.4949 46.9445 79.5409 46.8776 79.5491L46.6013 79.6241L46.5323 79.6428C46.4736 79.7181 46.3899 79.7556 46.2811 79.7555C46.1933 79.7595 46.1389 79.7595 46.1179 79.7553L45.8794 79.8052C45.8376 79.7968 45.7727 79.7946 45.6849 79.7986C45.5928 79.8236 45.5175 79.8194 45.459 79.7858L44.9383 79.6157L44.769 79.4837C44.4597 79.2909 44.2402 79.1379 44.1106 79.0247C44.0521 78.9912 44.0061 78.9493 43.9727 78.899C43.9602 78.853 43.9352 78.8153 43.8976 78.786C43.7849 78.5892 43.6848 78.3297 43.5973 78.0074C43.5182 77.7521 43.4579 77.4027 43.4167 76.9591L43.311 76.1871L43.3242 75.6348C43.3076 75.5009 43.3099 75.3817 43.3309 75.2771C43.3228 75.1014 43.3357 74.8211 43.3697 74.4362C43.374 74.3065 43.3889 74.1246 43.4143 73.8903C43.4397 73.656 43.4713 73.4448 43.5092 73.2566C43.5094 73.1478 43.5179 73.0516 43.5347 72.9679C43.5767 72.8676 43.5977 72.763 43.5979 72.6542L43.6926 72.1837C43.6929 71.9661 43.7035 71.805 43.7246 71.7005L43.826 70.8722C43.8597 70.7049 43.8851 70.4706 43.9023 70.1694C43.9317 70.023 43.955 69.7992 43.9721 69.498C43.9848 69.4353 43.9744 69.3788 43.941 69.3285L43.853 69.4414C43.7356 69.5918 43.6581 69.7068 43.6203 69.7862C43.6035 69.8699 43.5636 69.9598 43.5007 70.056C43.4421 70.1312 43.3981 70.1876 43.3687 70.2252L43.1361 70.5701C43.0481 70.6829 42.9601 70.7958 42.8721 70.9087C42.7841 71.0215 42.7086 71.126 42.6458 71.2222C42.4278 71.5482 42.2916 71.7384 42.2371 71.7927C42.2036 71.8513 42.1323 71.9348 42.0234 72.0435C42.0108 72.1062 41.9919 72.1459 41.9668 72.1626C41.9584 72.2045 41.8829 72.309 41.7405 72.4761C41.7321 72.518 41.6566 72.6225 41.5141 72.7896L40.9735 73.5295L40.4895 74.1502L40.0179 74.8713L39.7286 75.3353C39.6071 75.5067 39.5316 75.6112 39.5023 75.6488L39.3576 75.8808C39.3032 75.9352 39.2424 76.0208 39.1753 76.1379C39.1376 76.2173 39.0977 76.3073 39.0557 76.4076C39.018 76.4871 38.9698 76.5644 38.9111 76.6396C38.735 76.9741 38.6174 77.2877 38.5585 77.5805L38.4637 78.0511L38.3816 78.4589C38.3647 78.6513 38.4103 78.9108 38.5187 79.2373C38.5145 79.2582 38.5228 79.2708 38.5438 79.275C38.5605 79.3001 38.5667 79.3231 38.5625 79.344C38.5792 79.3691 38.5833 79.4026 38.5749 79.4444C38.5331 79.436 38.5143 79.4214 38.5185 79.4004C38.5018 79.3753 38.4683 79.3795 38.4181 79.4129C38.3636 79.4672 38.3113 79.4567 38.2612 79.3813L38.1296 79.2242ZM37.0771 77.8046C37.0562 77.8004 37.0478 77.7878 37.0521 77.7669L37.1089 77.4846L37.1276 77.5536L37.0834 77.7732C37.1001 77.7983 37.1085 77.8109 37.1085 77.8109C37.0876 77.8067 37.0771 77.8046 37.0771 77.8046ZM37.2026 77.8298C37.1817 77.8256 37.1733 77.8131 37.1775 77.7922L37.1337 77.6854L37.1841 77.5976L37.2154 77.6039C37.2279 77.65 37.2258 77.7148 37.2089 77.7985L37.2026 77.8298ZM37.203 77.5035C37.1905 77.4575 37.1591 77.4512 37.1089 77.4846L37.1655 77.3654C37.1697 77.3445 37.1823 77.3361 37.2032 77.3403C37.199 77.3613 37.1969 77.3717 37.1969 77.3717L37.2344 77.5098C37.2302 77.5307 37.2176 77.5391 37.1967 77.5349L37.203 77.5035ZM37.0158 76.6498L37.1228 76.4428L37.1291 76.4114L37.1228 76.4428C37.1017 76.5474 37.0765 76.6185 37.0472 76.6561L37.0158 76.6498ZM37.4607 77.1963C37.4816 77.2005 37.4942 77.1922 37.4984 77.1713C37.5235 77.1546 37.5424 77.1148 37.555 77.0521L37.5613 77.0207C37.5404 77.0165 37.5279 77.0249 37.5237 77.0458C37.4985 77.0625 37.4797 77.1022 37.467 77.165L37.4607 77.1963ZM38.2605 75.0071L38.2104 74.9317L38.1161 75.076L38.1474 75.0823L38.2605 75.0071ZM37.8106 73.5129C37.8986 73.4001 37.9551 73.3353 37.9802 73.3186L37.9866 73.2872L37.9802 73.3186L37.8356 73.5506C37.8147 73.5464 37.8021 73.5547 37.7979 73.5757L37.8106 73.5129ZM38.5251 74.1791C38.6298 74.0913 38.7011 73.9534 38.739 73.7651L38.7077 73.7588C38.6783 73.7964 38.649 73.834 38.6197 73.8717C38.5945 73.8884 38.5757 73.9281 38.563 73.9908C38.5462 74.0745 38.5231 74.1351 38.4938 74.1727L38.4875 74.2041L38.5251 74.1791ZM39.8755 73.3084C39.8964 73.3127 39.909 73.3043 39.9132 73.2834L40.0012 73.1705L40.0075 73.1392L39.9762 73.1329C39.9719 73.1538 39.9405 73.2018 39.8818 73.2771L39.8755 73.3084ZM41.0699 71.7536L41.0385 71.7473L40.9128 71.8852L40.9065 71.9165L40.9379 71.9229L41.0699 71.7536ZM40.4623 70.8805C40.5209 70.8053 40.5524 70.7572 40.5566 70.7363L40.5629 70.7049L40.4309 70.8742L40.4623 70.8805ZM41.1642 71.6094C41.1851 71.6136 41.1977 71.6052 41.2019 71.5843L41.2396 71.5593C41.424 71.2917 41.5728 71.0932 41.6859 70.9636C41.6901 70.9427 41.709 70.903 41.7425 70.8445C41.7761 70.7859 41.8054 70.7483 41.8305 70.7316L42.1198 70.2676L42.3398 69.9854L42.3461 69.9541C42.3252 69.9499 42.3127 69.9582 42.3085 69.9791L42.1388 70.1735L42.1198 70.2676C42.1198 70.2676 42.0947 70.2843 42.0444 70.3177C41.7427 70.7357 41.5268 71.0513 41.3968 71.2645L41.1705 71.578L41.1642 71.6094ZM44.4116 74.2869L44.3992 74.1865L44.3552 74.2429L44.3676 74.3434L44.4116 74.2869ZM44.7832 73.2519L44.7394 73.1452C44.7436 73.1243 44.7353 73.1117 44.7144 73.1075L44.708 73.1389L44.7142 73.2707C44.7351 73.2749 44.7434 73.2874 44.7392 73.3084L44.7832 73.2519ZM42.5725 69.6406L42.6731 69.465L42.6794 69.4336L42.5474 69.6029L42.5411 69.6343L42.5725 69.6406ZM44.7083 72.9757L44.7523 72.9193L44.7586 72.8879C44.7586 72.8879 44.7481 72.8858 44.7272 72.8816C44.7272 72.8816 44.7251 72.892 44.7209 72.913L44.6832 72.938C44.7166 72.9883 44.7333 73.0134 44.7333 73.0134L44.7083 72.9757ZM45.3182 72.0539L45.3371 71.9598L45.3057 71.9535L45.2744 71.9472L45.2177 72.0664L45.2491 72.0727L45.3182 72.0539ZM44.9238 71.2564L44.9491 71.1309L44.924 71.0933L44.9177 71.1246C44.8926 71.1413 44.8758 71.1706 44.8674 71.2124L44.8611 71.2438L44.8924 71.2501L44.9238 71.2564ZM44.7183 70.0073L44.7372 69.9132L44.7436 69.8818L44.7122 69.8755C44.6996 69.9382 44.6807 69.978 44.6556 69.9947C44.6514 70.0156 44.6702 70.0302 44.712 70.0387L44.7183 70.0073ZM45.44 69.9894L45.4777 69.9643L45.484 69.933L45.4213 69.9203C45.4213 69.9203 45.4108 69.9182 45.3899 69.914C45.3899 69.914 45.3878 69.9245 45.3836 69.9454C45.4003 69.9705 45.4045 70.004 45.396 70.0458L45.44 69.9894ZM45.4657 69.5376C45.4699 69.5167 45.472 69.5062 45.472 69.5062C45.4929 69.5104 45.5034 69.5125 45.5034 69.5125L45.5474 69.4561C45.5265 69.4519 45.5202 69.4289 45.5287 69.387L45.4973 69.3807L45.516 69.4498C45.5118 69.4707 45.4993 69.479 45.4783 69.4748L45.4657 69.5376ZM49.1713 72.2095L49.0582 72.2846L49.0833 72.3223L49.1713 72.2095ZM45.3953 65.6716C45.3995 65.6507 45.4016 65.6403 45.4016 65.6403C45.4225 65.6445 45.433 65.6466 45.433 65.6466L45.4206 65.5461L45.3766 65.6026L45.3953 65.6716ZM49.2033 71.7263C49.2368 71.6677 49.2871 71.6343 49.354 71.626L49.3289 71.5884L49.2976 71.582L49.1845 71.6572C49.1845 71.6572 49.1824 71.6677 49.1782 71.6886C49.1782 71.6886 49.1677 71.6865 49.1468 71.6823L49.2033 71.7263ZM49.3978 71.7328C49.4815 71.7496 49.5212 71.7141 49.5172 71.6263L49.5235 71.5949L49.5047 71.5258L49.4607 71.5823C49.4774 71.6074 49.4607 71.6366 49.4104 71.67L49.3664 71.7265L49.3978 71.7328ZM49.6119 71.1557L49.5869 71.118L49.4738 71.1932L49.5239 71.2685L49.6119 71.1557ZM49.8008 70.7041C49.8217 70.7083 49.8342 70.6999 49.8384 70.679C49.9221 70.6959 49.9702 70.6729 49.9829 70.6102C49.9871 70.5893 49.9787 70.5767 49.9578 70.5725L49.9201 70.5975C49.9117 70.6394 49.8887 70.6456 49.8511 70.6163L49.8071 70.6727L49.8008 70.7041ZM50.41 70.2718L50.454 70.2154L50.4667 70.1527L50.4103 70.1087L50.4039 70.14C50.4206 70.1652 50.4164 70.1861 50.3913 70.2028L50.3473 70.2592L50.41 70.2718ZM50.4231 69.8828L50.5677 69.6507L50.505 69.6381L50.4987 69.6695C50.5196 69.6737 50.5258 69.6967 50.5174 69.7385C50.4672 69.7719 50.4399 69.7991 50.4357 69.82L50.4168 69.9141L50.4231 69.8828ZM50.6176 69.8893C50.6385 69.8935 50.6511 69.8851 50.6553 69.8642L50.7433 69.7514L50.7496 69.72L50.7183 69.7137L50.5989 69.8202L50.6176 69.8893ZM50.7309 69.6509C50.7518 69.6552 50.7874 69.6406 50.8376 69.6072C50.8376 69.6072 50.8272 69.605 50.8063 69.6008C50.8105 69.5799 50.8105 69.5799 50.8063 69.6008C50.7644 69.5924 50.7393 69.6091 50.7309 69.6509ZM50.913 69.557L50.9256 69.4943L50.8566 69.513L50.8252 69.5067C50.821 69.5276 50.8084 69.536 50.7875 69.5318L50.844 69.5758L50.913 69.557ZM50.9635 69.3061L50.9572 69.3374C50.999 69.3459 51.0221 69.3396 51.0263 69.3187C51.0305 69.2978 51.0159 69.2622 50.9825 69.212L50.8945 69.3248L50.9635 69.3061ZM51.0389 69.256C51.0431 69.2351 51.0452 69.2246 51.0452 69.2246C51.0661 69.2288 51.0766 69.2309 51.0766 69.2309L51.0829 69.1995C51.0829 69.1995 51.0871 69.1786 51.0955 69.1368L51.0328 69.1242L51.0515 69.1932L51.0389 69.256ZM50.9827 69.0488L51.0393 68.9296L51.0456 68.8983L51.0143 68.8919L50.9576 69.0111L50.9513 69.0425L50.9827 69.0488ZM51.1709 69.0867C51.1751 69.0658 51.1793 69.0449 51.1835 69.0239C51.2129 68.9863 51.2527 68.9508 51.3029 68.9174L51.2591 68.8107L51.2278 68.8044L51.2088 68.8985L51.2025 68.9298C51.1774 68.9465 51.1606 68.9758 51.1522 69.0176C51.148 69.0385 51.1333 69.0574 51.1082 69.0741L51.1019 69.1054L51.1709 69.0867ZM51.3659 68.7669C51.3492 68.7418 51.3534 68.7208 51.3785 68.7041C51.4245 68.6916 51.4497 68.6749 51.4539 68.654L51.4665 68.5913L51.3974 68.61L51.3471 68.6978L51.2718 68.7479L51.3659 68.7669ZM51.6488 68.3342C51.653 68.3133 51.6656 68.3049 51.6865 68.3092L51.6238 68.2965C51.6238 68.2965 51.6133 68.2944 51.5924 68.2902C51.5924 68.2902 51.5903 68.3007 51.5861 68.3216L51.6048 68.3906L51.6488 68.3342ZM51.8187 67.9767C51.869 67.9433 51.8983 67.9057 51.9067 67.8639L51.7937 67.939C51.7895 67.9599 51.7978 67.9725 51.8187 67.9767ZM51.9505 67.9706C51.9924 67.979 52.0154 67.9728 52.0196 67.9519C52.0238 67.9309 52.0154 67.9184 51.9945 67.9142L51.9255 67.9329C51.9213 67.9538 51.9192 67.9643 51.9192 67.9643C51.9401 67.9685 51.9505 67.9706 51.9505 67.9706ZM52.3089 67.4878C52.3173 67.446 52.334 67.4167 52.3592 67.4L52.3278 67.3937L52.2775 67.4815L52.2712 67.5129L52.3089 67.4878ZM52.7493 66.5972C52.7493 66.5972 52.7744 66.5805 52.8247 66.5471L53.0196 66.2273L53.0322 66.1646L53.0386 66.1332C53.0134 66.1499 52.98 66.154 52.9381 66.1456L52.9004 66.1707C52.9339 66.2209 52.9506 66.246 52.9506 66.246C52.9463 66.267 52.9338 66.2753 52.9129 66.2711C52.892 66.2669 52.8794 66.2752 52.8752 66.2962C52.8541 66.4007 52.8185 66.4697 52.7682 66.5031L52.7493 66.5972ZM52.9137 65.6184C52.9891 65.5683 53.0268 65.5433 53.0268 65.5433L52.9703 65.4993C52.9661 65.5202 52.9389 65.5473 52.8886 65.5807L52.9137 65.6184ZM53.0897 65.3927C53.0939 65.3718 53.0856 65.3593 53.0647 65.355L53.0206 65.4115L53.0394 65.4805L53.0897 65.3927ZM53.2154 65.2548L53.159 65.2108L53.1213 65.2359C53.1213 65.2359 53.1192 65.2463 53.115 65.2672C53.115 65.2672 53.1254 65.2694 53.1463 65.2736L53.2154 65.2548ZM54.151 64.823L54.2641 64.7478L54.2075 64.867L54.1698 64.892L54.151 64.823ZM54.6085 65.3068C54.6127 65.2859 54.64 65.2587 54.6902 65.2253L54.6652 65.1876C54.6233 65.1792 54.5982 65.1959 54.5898 65.2377L54.6085 65.3068ZM54.2641 64.7478C54.2767 64.6851 54.26 64.66 54.214 64.6724C54.2182 64.6515 54.2454 64.6244 54.2957 64.591L54.327 64.5973C54.3312 64.5764 54.3543 64.5701 54.3961 64.5785C54.3877 64.6204 54.3709 64.6496 54.3458 64.6663C54.3416 64.6873 54.3143 64.7144 54.2641 64.7478ZM54.4969 64.2398L54.5849 64.1269L54.61 64.1646L54.4906 64.2712L54.4969 64.2398ZM51.1106 82.0661L51.0984 81.8025C51.1152 81.7188 51.1048 81.6623 51.0672 81.633L51.0798 81.5703L51.143 81.2566C51.2101 81.1395 51.2499 81.0496 51.2626 80.9868C51.271 80.945 51.248 80.8969 51.1937 80.8424C51.1728 80.8382 51.154 80.8235 51.1373 80.7984C51.1415 80.7775 51.1457 80.7566 51.1499 80.7357L51.1626 80.6729C51.1752 80.6102 51.2087 80.5517 51.2632 80.4973C51.3134 80.4639 51.3532 80.4284 51.3826 80.3908C51.4161 80.3323 51.5356 80.1714 51.7409 79.908C51.8582 79.7576 51.9379 79.6322 51.9799 79.5318L52.0112 79.5381L52.0803 79.5194C52.0887 79.4775 52.1222 79.419 52.1809 79.3438L52.5205 78.7919L52.5268 78.7606C52.5771 78.7272 52.6043 78.7 52.6085 78.6791C52.6378 78.6415 52.6546 78.6122 52.6588 78.5913L52.8538 78.2715L52.967 78.0332L52.9734 78.0018C52.9734 78.0018 52.9629 77.9997 52.942 77.9955C52.942 77.9955 52.9399 78.0059 52.9357 78.0268L52.7597 78.2525C52.7597 78.2525 52.7492 78.2504 52.7283 78.2462C52.7283 78.2462 52.7262 78.2567 52.722 78.2776L52.7283 78.2462L52.7409 78.1835L52.7032 78.2085L52.6719 78.2022L52.6782 78.1708L52.8542 77.9451L53.0805 77.6316C53.1392 77.5564 53.1706 77.5083 53.1748 77.4874L53.4389 77.1489L53.4264 77.0484L53.3511 77.0986L53.2694 77.18L53.2883 77.0859L53.2946 77.0546L53.2883 77.0859C53.1501 77.2322 53.0663 77.3241 53.0369 77.3617C52.9867 77.3951 52.9197 77.4578 52.8359 77.5498C52.7563 77.6208 52.6976 77.696 52.6599 77.7755L52.5845 77.8256L52.5971 77.7628C52.6935 77.6081 52.7543 77.5225 52.7794 77.5058C52.8674 77.3929 52.9324 77.2863 52.9744 77.1859C53.0373 77.0898 53.0981 77.0041 53.1567 76.9289C53.2154 76.8536 53.2489 76.7951 53.2574 76.7533L53.2637 76.7219L53.2574 76.7533L53.226 76.747L53.182 76.8034L53.1946 76.7406L53.2072 76.6779L53.2136 76.6465C53.1926 76.6423 53.1801 76.6507 53.1759 76.6716C53.155 76.6674 53.1424 76.6757 53.1382 76.6966L53.1508 76.6339L53.2138 76.4834C53.218 76.4624 53.2096 76.4499 53.1887 76.4457C53.1887 76.4457 53.1783 76.4436 53.1573 76.4394C53.1573 76.4394 53.1552 76.4498 53.151 76.4707C53.0966 76.5251 53.0358 76.6107 52.9687 76.7278L52.711 77.035L52.315 77.5428L51.479 78.6149C51.3994 78.6859 51.3407 78.7612 51.303 78.8406C51.2694 78.8991 51.238 78.9472 51.2086 78.9848C51.1584 79.0182 51.1291 79.0558 51.1206 79.0977L50.8063 79.524C50.7812 79.5407 50.7644 79.57 50.756 79.6118L50.7246 79.6055C50.7246 79.6055 50.7142 79.6034 50.6932 79.5992C50.6975 79.5783 50.71 79.5699 50.7309 79.5741C50.8987 79.2815 51.0119 79.0975 51.0705 79.0223L51.7495 78.0818L52.4725 77.0849L52.4914 76.9908L52.4474 77.0472L52.3657 77.1287L51.976 77.6051C51.9425 77.6637 51.823 77.8246 51.6177 78.0879L51.624 78.0565L51.7623 77.8559L51.819 77.7367L51.8253 77.7054C51.7835 77.6969 51.773 77.6948 51.7939 77.699C51.819 77.6823 51.8337 77.6635 51.8379 77.6426L51.8884 77.3917L51.6497 77.6047C51.6288 77.6005 51.6141 77.6193 51.6057 77.6612C51.589 77.636 51.5848 77.6026 51.5933 77.5607C51.6017 77.5189 51.6352 77.4604 51.6939 77.3851L51.9769 76.9525C52.0062 76.9149 52.0293 76.8542 52.0461 76.7706L52.1781 76.6013L52.1844 76.5699L52.1531 76.5636L51.9394 76.8144L51.8703 76.8331C51.8745 76.8122 51.8557 76.7975 51.8139 76.7891C51.7972 76.764 51.8014 76.7431 51.8265 76.7264L52.0905 76.3878L52.7255 75.5037L52.9455 75.2216L52.9581 75.1589L52.8891 75.1776L52.7508 75.3782C52.7466 75.3992 52.734 75.4075 52.7131 75.4033L52.7194 75.3719L52.732 75.3092L52.7007 75.3029C52.642 75.3781 52.5875 75.4324 52.5373 75.4658L52.5436 75.4345L52.7259 75.1774C52.7553 75.1398 52.8181 75.0436 52.9146 74.8889L53.2855 74.3434L53.8451 73.5095C54.0211 73.2838 54.1427 73.1124 54.2098 72.9953L54.7504 72.2555L55.2283 71.503L55.813 70.7067L56.6115 69.4965L57.0455 68.8005L57.9446 67.4147C58.171 67.0468 58.3701 66.7605 58.5419 66.5557C58.5964 66.5013 58.741 66.3237 58.9756 66.0228L59.227 65.747L59.491 65.4084C59.5832 65.2747 59.7046 65.212 59.8552 65.2206C59.8762 65.2248 59.9096 65.2207 59.9557 65.2082C60.0059 65.1748 60.052 65.1623 60.0938 65.1707C60.2068 65.1499 60.2821 65.1542 60.3197 65.1835C60.3406 65.1878 60.3699 65.2045 60.4075 65.2339C60.4493 65.2423 60.5037 65.2424 60.5707 65.2341C60.6209 65.2007 60.6606 65.2195 60.6898 65.2907C60.7484 65.3242 60.8111 65.3369 60.8781 65.3286L61.104 65.3414C61.1876 65.3583 61.2503 65.4253 61.292 65.5425L61.3484 65.5865C61.3943 65.6828 61.4591 65.7393 61.5427 65.7562C61.6515 65.7563 61.7268 65.7606 61.7686 65.769C61.9484 65.8487 62.0718 65.9389 62.1386 66.0394C62.2806 66.1985 62.3975 66.3744 62.4893 66.567C62.5896 66.7177 62.6397 66.7931 62.6397 66.7931C62.6564 66.8182 62.7107 66.8727 62.8026 66.9565C62.836 67.0067 62.8527 67.0318 62.8527 67.0318L62.9717 67.2516C63.0552 67.3772 63.0321 67.4379 62.9024 67.4335C62.8146 67.4376 62.7287 67.4856 62.6449 67.5775C62.5863 67.6528 62.5172 67.6715 62.4378 67.6338C62.3332 67.6127 62.2642 67.6315 62.2306 67.69C62.2264 67.7109 62.2034 67.7171 62.1616 67.7087L62.0424 67.6521C61.9796 67.6395 61.9399 67.6206 61.9232 67.5955C61.8438 67.5577 61.7768 67.566 61.7224 67.6203C61.4962 67.7706 61.3077 67.9503 61.1569 68.1593C61.0731 68.2512 60.9725 68.3724 60.8552 68.5229C60.742 68.6525 60.6226 68.8134 60.4968 69.0057L59.8682 69.8584L59.3966 70.5795L58.9816 71.1814C58.9565 71.1981 58.9125 71.2546 58.8496 71.3507C58.8077 71.4511 58.7385 71.5242 58.6422 71.5701C58.6171 71.5868 58.5982 71.6265 58.5856 71.6893C58.5018 71.7812 58.4474 71.8355 58.4222 71.8522C58.372 71.8856 58.2882 71.9776 58.1709 72.128L57.7685 72.6672L57.4102 73.15L57.0015 73.7206L56.6432 74.2034C56.4714 74.4081 56.2346 74.7195 55.9329 75.1375L55.3608 75.8711L54.9208 76.4353L54.5562 76.9495C54.5184 77.0289 54.466 77.1272 54.3989 77.2442C54.3318 77.3613 54.2396 77.4951 54.1223 77.6455C54.0845 77.725 54.0237 77.8107 53.94 77.9026C53.8813 77.9778 53.8184 78.074 53.7513 78.191L53.2043 78.9623L52.9907 79.213L52.9277 79.3636L52.7831 79.5956L52.6574 79.7335L52.6511 79.7648C52.5757 79.815 52.494 79.8964 52.406 80.0093C52.318 80.1221 52.2468 80.2057 52.1923 80.26L51.9723 80.5422C51.8047 80.7261 51.6873 80.9309 51.6201 81.1567L51.6388 81.2258C51.6973 81.2594 51.7015 81.2928 51.6512 81.3262C51.5674 81.4182 51.515 81.5164 51.494 81.621C51.452 81.7213 51.364 81.8342 51.23 81.9595C51.2173 82.0223 51.1984 82.062 51.1733 82.0787L51.1293 82.1351L51.1106 82.0661ZM51.0625 80.359L51.0689 80.3277L51.1129 80.2712L51.1316 80.3403L51.1253 80.3717L51.0436 80.4531L51.0625 80.359ZM51.4826 80.7047L51.5078 80.5792L51.5205 80.5165L51.5331 80.4538L51.4891 80.5102C51.4598 80.5478 51.4367 80.6084 51.4198 80.6921L51.4386 80.7611L51.4826 80.7047ZM51.5453 80.7174C51.5411 80.7383 51.5495 80.7508 51.5704 80.755C51.5913 80.7592 51.6039 80.7509 51.6081 80.73C51.6499 80.7384 51.675 80.7217 51.6834 80.6799C51.6876 80.659 51.6773 80.6025 51.6523 80.5104L51.5643 80.6232L51.5266 80.6483C51.5182 80.6901 51.5244 80.7131 51.5453 80.7174ZM51.3514 80.2213C51.4185 80.1043 51.4835 79.9977 51.5464 79.9015L51.584 79.8765C51.5798 79.8974 51.5777 79.9078 51.5777 79.9078C51.5944 79.933 51.5902 79.9539 51.5651 79.9706C51.54 79.9873 51.5232 80.0165 51.5148 80.0584C51.5022 80.1211 51.4812 80.1713 51.4518 80.2089C51.4434 80.2507 51.4099 80.3093 51.3512 80.3845L51.3198 80.3782L51.3514 80.2213ZM51.8279 80.611C51.8488 80.6152 51.8613 80.6069 51.8656 80.586L51.9662 80.4104C51.9746 80.3686 51.9893 80.3497 52.0102 80.354L51.9851 80.3163L51.9034 80.3977L51.8971 80.4291C51.8845 80.4919 51.8635 80.542 51.8342 80.5797L51.8279 80.611ZM51.2828 79.9137C51.2912 79.8719 51.3122 79.8217 51.3457 79.7632C51.4044 79.688 51.4484 79.6315 51.4777 79.5939L51.7607 79.1612C51.79 79.1236 51.8131 79.063 51.8299 78.9793L51.8676 78.9543L51.8613 78.9857C51.8571 79.0066 51.855 79.017 51.855 79.017C51.8759 79.0212 51.8864 79.0233 51.8864 79.0233C51.9282 79.0318 51.9344 79.0548 51.9051 79.0924L51.6851 79.3745C51.6642 79.3703 51.6516 79.3787 51.6474 79.3996L51.6661 79.4686C51.6704 79.4477 51.6829 79.4394 51.7038 79.4436L51.7165 79.3808C51.7374 79.3851 51.7457 79.3976 51.7415 79.4185C51.7331 79.4604 51.7163 79.4896 51.6912 79.5063L51.5215 79.7007L51.5089 79.7634C51.5089 79.7634 51.5068 79.7739 51.5026 79.7948C51.4984 79.8157 51.5088 79.8178 51.5339 79.8011L51.5276 79.8325L51.3455 79.9264C51.3413 79.9473 51.3287 79.9556 51.3078 79.9514L51.2701 79.9765L51.2828 79.9137ZM52.0306 79.1177L51.886 79.3497L51.8546 79.3434L52.0306 79.1177ZM52.2805 79.984C52.3014 79.9882 52.314 79.9799 52.3182 79.959L52.5382 79.6768L52.5068 79.6705L52.2555 79.9463C52.2764 79.9506 52.2847 79.9631 52.2805 79.984ZM51.9864 79.3373C51.9906 79.3163 51.9822 79.3038 51.9613 79.2996L52.1813 79.0174C52.2022 79.0217 52.2148 79.0133 52.219 78.9924L52.2127 79.0238L51.9927 79.3059L51.9864 79.3373ZM52.1752 78.8856L52.1815 78.8543C52.1773 78.8752 52.1752 78.8856 52.1752 78.8856C52.1961 78.8899 52.2066 78.892 52.2066 78.892L52.0306 79.1177L52.1752 78.8856ZM52.1946 78.4652C52.203 78.4234 52.2198 78.3941 52.2449 78.3774L52.358 78.3022L52.3516 78.3336L52.3076 78.39L52.226 78.4715L52.2196 78.5029L52.1946 78.4652ZM52.2759 78.7101C52.301 78.6933 52.3178 78.6641 52.3262 78.6223L52.4582 78.453L52.5336 78.4029L52.5146 78.497L52.3009 78.7477L52.2695 78.7414L52.2759 78.7101ZM52.4148 78.0199C52.419 77.999 52.4462 77.9718 52.4965 77.9384C52.5007 77.9175 52.5133 77.9092 52.5342 77.9134L52.5279 77.9447L52.4462 78.0262C52.442 78.0471 52.4294 78.0555 52.4085 78.0513L52.4148 78.0199ZM53.011 77.9767C53.0153 77.9558 53.0174 77.9454 53.0174 77.9454C53.0383 77.9496 53.0487 77.9517 53.0487 77.9517L53.1871 77.751L53.1934 77.7197C53.1934 77.7197 53.1829 77.7175 53.162 77.7133C53.162 77.7133 53.1599 77.7238 53.1557 77.7447L53.03 77.8826L53.011 77.9767ZM52.8365 77.0602C52.8616 77.0435 52.8763 77.0247 52.8805 77.0038C52.8889 76.962 52.9057 76.9327 52.9308 76.916L52.9685 76.891L52.9559 76.9537L52.8679 77.0666C52.8679 77.0666 52.8574 77.0645 52.8365 77.0602C52.8365 77.0602 52.8344 77.0707 52.8302 77.0916L52.8365 77.0602ZM53.5332 77.0047C53.5583 76.9879 53.5772 76.9482 53.5898 76.8855C53.5396 76.9189 53.5123 76.9461 53.5081 76.967L53.5018 76.9983L53.5332 77.0047ZM55.1343 76.3477L55.2914 76.2161L55.2851 76.2475L55.1657 76.3541C55.1615 76.375 55.1489 76.3833 55.128 76.3791L55.1343 76.3477ZM62.334 87.3287C62.2168 87.3704 62.1352 87.3431 62.0893 87.2468L62.0579 87.2405C61.991 87.2487 61.9325 87.2152 61.8823 87.1398C61.8656 87.1147 61.8385 87.0875 61.8009 87.0581C61.7842 87.033 61.7549 87.0162 61.7131 87.0078C61.6587 86.9534 61.6232 86.9136 61.6065 86.8884C61.6192 86.8257 61.5941 86.788 61.5314 86.7754L61.5063 86.7377L61.5255 86.4804C61.513 86.4344 61.513 86.38 61.5257 86.3172L61.7206 85.9974L61.7145 85.8656L61.7271 85.8029L61.9657 85.753L62.0284 85.7656L62.0661 85.7406C62.0327 85.6903 62.0349 85.6255 62.0726 85.546C62.1062 85.4875 62.1272 85.4373 62.1356 85.3955C62.1565 85.3997 62.1649 85.4123 62.1606 85.4332L62.2234 85.4458C62.2485 85.4291 62.2674 85.3894 62.28 85.3266L62.255 85.289C62.2216 85.2387 62.2091 85.1927 62.2175 85.1508L62.2301 85.0881L62.3053 85.2012C62.322 85.2263 62.3429 85.2305 62.368 85.2138C62.4141 85.2013 62.4392 85.1846 62.4434 85.1637L62.4874 85.1073C62.4999 85.1533 62.5082 85.1659 62.5125 85.1449C62.5376 85.1282 62.5606 85.122 62.5815 85.1262C62.6024 85.1304 62.615 85.1221 62.6192 85.1011C62.6234 85.0802 62.636 85.0719 62.6569 85.0761L62.6005 85.0321L62.544 84.9881L62.5693 84.8626L62.5819 84.7999L62.5379 84.8563L62.5253 84.919C62.5253 84.919 62.5002 84.9357 62.4499 84.9691L62.3935 84.9251L62.4689 84.875L62.5255 84.7559C62.5757 84.7225 62.6009 84.7058 62.6009 84.7058L62.6196 84.7748C62.6363 84.7999 62.6383 84.8439 62.6257 84.9066C62.676 84.8732 62.7011 84.8565 62.7011 84.8565C62.8016 84.7897 62.8686 84.727 62.9022 84.6685L62.8771 84.6308L62.8708 84.6622L62.7704 84.6746L62.7893 84.5805C62.8144 84.5638 62.8312 84.5345 62.8396 84.4927C62.8438 84.4718 62.8585 84.453 62.8836 84.4363L62.8963 84.3735L62.8272 84.3923C62.823 84.4132 62.8104 84.4215 62.7895 84.4173L62.7958 84.3859L62.9152 84.2794C62.9906 84.2293 63.0199 84.1917 63.0032 84.1666C62.9991 84.0787 63.0452 84.0118 63.1415 83.9659L63.1668 83.8404L63.1417 83.8027L63.2801 83.6021C63.2843 83.5812 63.2968 83.5728 63.3177 83.577L63.3114 83.6084L63.3365 83.6461L63.3428 83.6147C63.3973 83.5604 63.4078 83.5081 63.3744 83.4579C63.3577 83.4327 63.3556 83.3888 63.3683 83.3261C63.4227 83.2717 63.4186 83.2383 63.3558 83.2256C63.3558 83.2256 63.3454 83.2235 63.3245 83.2193C63.3245 83.2193 63.3266 83.2089 63.3308 83.188C63.3517 83.1922 63.3643 83.1838 63.3685 83.1629C63.4312 83.1755 63.4794 83.1526 63.5129 83.0941C63.5464 83.0355 63.5653 82.9958 63.5695 82.9749C63.5737 82.954 63.5801 82.9226 63.5885 82.8808C63.6136 82.8641 63.645 82.8704 63.6826 82.8997L63.7203 82.8747C63.7203 82.8747 63.7454 82.858 63.7956 82.8246L63.802 82.7932L63.7832 82.7241L63.7392 82.7806L63.7203 82.8747C63.666 82.8202 63.6639 82.7763 63.7142 82.7429L63.8022 82.63C63.8273 82.6133 63.8315 82.5924 63.8148 82.5673C63.7563 82.5337 63.7563 82.4793 63.815 82.4041C63.8401 82.3874 63.8569 82.3581 63.8653 82.3163C63.8989 82.2578 63.9387 82.2223 63.9847 82.2098C64.0098 82.1931 64.0119 82.1826 63.991 82.1784C63.9785 82.1324 63.9848 82.101 64.01 82.0843C64.0393 82.0467 64.0582 82.007 64.0666 81.9651L64.098 81.9714L64.0917 82.0028L64.123 82.0091C64.1272 81.9882 64.1293 81.9778 64.1293 81.9778C64.1545 81.9611 64.1587 81.9401 64.142 81.915L64.1546 81.8523L64.2237 81.8335L64.255 81.8398C64.2592 81.8189 64.2509 81.8064 64.23 81.8022L64.2112 81.7331L64.2239 81.6704L64.1485 81.7205C64.1149 81.779 64.0793 81.848 64.0415 81.9274C64.008 81.986 63.9619 82.0529 63.9032 82.1281C63.899 82.149 63.8864 82.1574 63.8655 82.1531L63.8719 82.1218L63.9285 82.0026L63.8028 82.1405L63.6958 82.3475L63.6582 82.3725L63.5577 82.385C63.5662 82.3431 63.5829 82.3139 63.608 82.2972L63.671 82.1466L63.6333 82.1717L63.5956 82.1967L63.6083 82.134C63.6629 81.9709 63.7509 81.8036 63.8725 81.6323L63.86 81.5318C63.8182 81.5234 63.7952 81.5297 63.791 81.5506L63.6592 81.5567C63.6425 81.5316 63.6111 81.5252 63.5651 81.5377C63.5442 81.5335 63.5233 81.5293 63.5023 81.5251L63.0379 81.5622C62.9458 81.5872 62.9039 81.6331 62.9122 81.7001C62.8495 81.6874 62.8244 81.6498 62.837 81.587L62.812 81.5493L62.7932 81.4803C62.8269 81.313 62.7643 81.2459 62.6052 81.2792C62.6052 81.2792 62.5801 81.2959 62.5299 81.3293C62.4838 81.3418 62.4357 81.3104 62.3856 81.235L62.3543 81.2287L62.1033 81.1782C61.9569 81.1487 61.8377 81.1464 61.7456 81.1714L61.7142 81.1651C61.6221 81.1901 61.5092 81.2109 61.3752 81.2274C61.2456 81.2231 61.1347 81.2334 61.0426 81.2584L60.7664 81.3334L60.4775 81.4711C60.4775 81.4711 60.4754 81.4815 60.4712 81.5024C60.4712 81.5024 60.4607 81.5003 60.4398 81.4961L60.3958 81.5525L60.3771 81.4835L60.4023 81.358C60.4317 81.3204 60.4254 81.2974 60.3836 81.2889L60.2895 81.27C60.2477 81.2616 60.231 81.2364 60.2394 81.1946L60.2834 81.1382L60.8986 81.0009C60.9613 81.0135 61.0157 81.0136 61.0618 81.0011C61.0827 81.0053 61.0952 80.997 61.0994 80.9761L61.0367 80.9634C60.9573 80.9257 60.8339 80.89 60.6666 80.8563L60.3842 80.7994C60.2587 80.7742 60.1625 80.7657 60.0956 80.774L59.8507 80.8552L59.8194 80.8489C59.8111 80.782 59.7735 80.7526 59.7065 80.7609C59.6438 80.7483 59.6019 80.7399 59.581 80.7357C59.4764 80.7146 59.4011 80.7103 59.3551 80.7228L59.2924 80.7102C59.1251 80.6765 59.0603 80.5656 59.0982 80.3773C59.0942 80.2895 59.134 80.2539 59.2176 80.2708C59.2385 80.275 59.2741 80.2604 59.3244 80.227C59.291 80.1767 59.2742 80.1516 59.2742 80.1516C59.2827 80.1098 59.2785 80.0763 59.2618 80.0512L59.3496 80.1015C59.4667 80.1686 59.5461 80.2064 59.588 80.2148C59.7344 80.2443 59.8515 80.257 59.9393 80.2529L60.0398 80.2405C59.9897 80.1651 59.9646 80.1274 59.9646 80.1274L59.7136 80.0769C59.676 80.0475 59.6258 80.0266 59.5631 80.0139C59.5464 79.9888 59.5067 79.9699 59.4439 79.9573C59.4021 79.9489 59.3582 79.9509 59.3121 79.9634C59.2661 79.9759 59.2243 79.9675 59.1867 79.9381C59.17 79.913 59.149 79.9088 59.1239 79.9255C59.0988 79.9422 59.082 79.9715 59.0736 80.0133C59.0736 80.0133 59.0715 80.0238 59.0673 80.0447C59.0673 80.0447 59.0568 80.0426 59.0359 80.0384L59.0547 80.1074L59.0483 80.1388L59.017 80.1325L59.0045 80.032C59.0256 79.9275 59.0173 79.8605 58.9797 79.8312L58.961 79.7621C59.0112 79.7287 58.9987 79.6827 58.9235 79.624C58.8817 79.6156 58.8586 79.6218 58.8544 79.6428C58.846 79.6846 58.823 79.6908 58.7854 79.6615L58.6788 79.5421C58.683 79.5212 58.6642 79.5065 58.6224 79.4981L58.6098 79.5609L58.6035 79.5922C58.5825 79.588 58.5742 79.5755 58.5784 79.5545L58.3215 79.2091L58.0272 78.7255C58.0314 78.7045 58.0231 78.692 58.0021 78.6878C57.9227 78.65 57.8684 78.5956 57.8392 78.5244C57.8351 78.4365 57.8247 78.38 57.808 78.3549L57.7017 78.0724C57.5768 77.612 57.5479 77.2689 57.6151 77.043L57.7036 76.6038L57.7476 76.5474L57.8669 76.4409C57.8459 76.5455 57.8394 76.6856 57.8476 76.8613C57.8434 76.8822 57.858 76.9178 57.8914 76.9681L57.9103 76.874C57.8811 76.8028 57.9022 76.6982 57.9735 76.5603L57.9674 76.4285L58.0996 76.096L58.3703 75.3998L58.3766 75.3684L58.3829 75.337C58.3829 75.337 58.3725 75.3349 58.3516 75.3307C58.3516 75.3307 58.3495 75.3412 58.3453 75.3621L58.2133 75.5313L58.5215 74.9732L58.7728 74.6974L58.9049 74.5281L59.1375 74.1832L59.1501 74.1205L59.1375 74.1832C59.1166 74.179 59.1061 74.1769 59.1061 74.1769C59.1103 74.156 59.1124 74.1456 59.1124 74.1456L59.1501 74.1205C59.2004 74.0871 59.2318 74.039 59.2444 73.9763L59.3638 73.8697L59.4581 73.7255C59.4623 73.7046 59.4666 73.6837 59.4708 73.6628C59.5001 73.6252 59.5252 73.6085 59.5461 73.6127C59.5922 73.6002 59.6299 73.5751 59.6592 73.5375C59.6927 73.479 59.7221 73.4414 59.7472 73.4247L59.9483 73.2366C59.9525 73.2157 59.9546 73.2053 59.9546 73.2053C59.9797 73.1886 59.9818 73.1781 59.9609 73.1739L59.9735 73.1112C60.0238 73.0777 60.0636 73.0422 60.0929 73.0046C60.1222 72.967 60.1516 72.9294 60.1809 72.8918L60.9098 72.1898L61.2993 71.8765C61.7768 71.4504 62.0155 71.2373 62.0155 71.2373L62.5998 70.7674L63.2404 70.3414C63.2949 70.2871 63.3933 70.2308 63.5356 70.1724L63.4539 70.2538L63.3032 70.3541L63.0644 70.5671L62.7943 70.7739L62.7817 70.8366L62.813 70.843C62.8172 70.822 62.8298 70.8137 62.8507 70.8179L62.8947 70.7615C62.9156 70.7657 62.9512 70.7511 63.0015 70.7177L63.1962 70.561C63.3972 70.4274 63.4977 70.3606 63.4977 70.3606C63.7741 70.1769 63.9123 70.085 63.9123 70.085C63.9374 70.0683 63.9751 70.0432 64.0253 70.0098C64.1007 69.9597 64.1447 69.9033 64.1573 69.8405L64.195 69.8155C64.2577 69.8281 64.3184 69.7968 64.3771 69.7216C64.3855 69.6798 64.4107 69.6631 64.4525 69.6715L64.7037 69.5588L65.0115 69.327L65.0868 69.2769L65.0932 69.2455L65.0618 69.2392L64.9487 69.3144L64.5028 69.5837L64.0569 69.853C64.0569 69.853 63.969 69.9114 63.7931 70.0284L63.5733 70.1473C63.5691 70.1682 63.5461 70.1745 63.5042 70.1661C63.5042 70.1661 63.567 70.1243 63.6927 70.0408L63.699 70.0094L63.6676 70.0031L63.1526 70.2911L63.0208 70.2972C63.0208 70.2972 63.046 70.2805 63.0962 70.2471L63.1402 70.1907C63.1611 70.1949 63.1737 70.1866 63.1779 70.1656C63.1403 70.1363 63.1361 70.1028 63.1655 70.0652C63.1948 70.0276 63.2116 69.9983 63.2158 69.9774L63.2472 69.9837L63.4105 69.8208L64.2019 69.2946C64.2019 69.2946 64.3652 69.186 64.6919 68.9689L65.4833 68.4427L65.9229 68.2048L66.7267 67.7791C66.8021 67.729 66.8732 67.6998 66.9402 67.6915C67.0114 67.6623 67.0721 67.631 67.1223 67.5976L67.4865 67.4098C67.7796 67.2512 68.0078 67.1448 68.171 67.0906C68.5561 66.907 68.8534 66.7819 69.0626 66.7152L69.7281 66.4901L70.1425 66.3777L70.4313 66.24L70.8771 66.1339C70.9231 66.1214 70.9817 66.1005 71.0529 66.0713C71.1449 66.0463 71.237 66.0214 71.3291 65.9964C71.4254 65.9505 71.5467 65.9423 71.6931 65.9717C71.781 65.9677 71.8542 65.9824 71.9127 66.0159C71.9754 66.0286 72.0277 66.0391 72.0695 66.0475L72.4083 66.1484C72.5129 66.1694 72.6446 66.2177 72.8035 66.2932C73.0126 66.3353 73.1569 66.3752 73.2364 66.413L73.4934 66.5953L73.7566 66.9094L73.9697 67.1482C74.0198 67.2236 74.049 67.2947 74.0573 67.3617C74.0865 67.4328 74.1178 67.4935 74.1512 67.5438L74.1449 67.5752C74.2117 67.6756 74.2304 67.7991 74.2009 67.9455C74.1923 68.0961 74.1817 68.2028 74.1691 68.2655L74.1565 68.3283L74.0683 68.6043C74.0598 68.6461 74.0431 68.6754 74.0179 68.6921C73.9426 68.7422 73.8818 68.8279 73.8356 68.9491C73.7894 69.0704 73.7496 69.1603 73.716 69.2188C73.6825 69.2774 73.6573 69.3485 73.6405 69.4321C73.6236 69.5158 73.5984 69.5869 73.5649 69.6454C73.5438 69.75 73.4956 69.8273 73.4202 69.8774C73.3491 69.9066 73.2548 69.9964 73.1375 70.1469C73.0286 70.2556 72.9217 70.4081 72.8168 70.6046C72.7624 70.659 72.6974 70.7656 72.6219 70.9245L72.6093 70.9872C72.6427 71.0374 72.63 71.1002 72.5714 71.1754L71.748 72.1848L71.3772 72.5671L71.1761 72.7551L70.6986 73.1813C70.64 73.2565 70.5625 73.3171 70.4662 73.363C70.3908 73.4131 70.3238 73.4758 70.2652 73.551C70.1814 73.6429 70.1081 73.6826 70.0454 73.6699C70.0244 73.6657 69.991 73.6699 69.9449 73.6824C69.9198 73.6991 69.8989 73.6949 69.8822 73.6697L69.8508 73.6634C69.7921 73.7387 69.7231 73.7574 69.6436 73.7196C69.5642 73.6819 69.5036 73.6588 69.4617 73.6504C69.3572 73.6293 69.2778 73.5372 69.2236 73.3739L69.1986 73.3363L69.1609 73.3613C69.098 73.4575 69.0038 73.4929 68.8783 73.4676C68.8574 73.4634 68.8135 73.4655 68.7465 73.4737C68.7005 73.4862 68.6608 73.4674 68.6274 73.4171C68.6022 73.4338 68.5688 73.438 68.5269 73.4295C68.4851 73.4211 68.4454 73.4022 68.4078 73.3729C68.3953 73.3269 68.3577 73.2975 68.2949 73.2849C68.2531 73.2765 68.2155 73.2471 68.1821 73.1969C68.1487 73.1466 68.1131 73.1069 68.0755 73.0775C68.0003 73.0189 67.9522 72.9874 67.9313 72.9832C67.8352 72.9203 67.7767 72.8324 67.7559 72.7194C67.7603 72.5897 67.7918 72.4872 67.8504 72.412C67.884 72.3535 67.9133 72.3159 67.9385 72.2992C67.9678 72.2615 67.995 72.2344 68.0201 72.2177C68.0955 72.1676 68.171 72.0631 68.2465 71.9042L68.6677 71.2709L69.3029 70.2236L69.7179 69.6217C69.7305 69.5589 69.7494 69.5192 69.7745 69.5025L69.7871 69.4398L69.7244 69.4271C69.6281 69.473 69.4879 69.521 69.3038 69.571C68.7847 69.7711 68.3975 69.9108 68.1422 69.99C67.9999 70.0483 67.8555 70.1172 67.7089 70.1965C67.5624 70.2758 67.3845 70.3488 67.1752 70.4155C67.104 70.4447 67.0224 70.4718 66.9304 70.4967C66.8383 70.5217 66.7441 70.5572 66.6478 70.6031C66.2711 70.7448 65.9822 70.8825 65.7812 71.0162L64.814 71.6049L64.3367 71.8678L63.9098 72.043C63.7507 72.0763 63.6251 72.1598 63.5329 72.2936C63.5078 72.3103 63.401 72.4084 63.2125 72.5881C63.204 72.6299 63.1873 72.6592 63.1621 72.6759C63.1537 72.7177 63.1391 72.7365 63.1181 72.7323L62.9234 72.889C62.9025 72.8848 62.8669 72.8994 62.8167 72.9328C62.7162 72.9996 62.6659 73.033 62.6659 73.033C62.5654 73.0998 62.5152 73.1332 62.5152 73.1332C62.5152 73.1332 62.49 73.1499 62.4398 73.1833C62.4356 73.2042 62.4188 73.2335 62.3895 73.2711C62.3644 73.2878 62.3309 73.292 62.2891 73.2835C62.3058 73.3087 62.2911 73.3275 62.245 73.34C62.2199 73.3567 62.2074 73.365 62.2074 73.365C62.1571 73.3984 62.0608 73.4987 61.9183 73.6659L61.5852 74.0232C61.4805 74.1109 61.3988 74.1924 61.3402 74.2676C61.3024 74.3471 61.2563 74.414 61.2018 74.4683L60.9252 74.8696C60.8874 74.949 60.8518 75.018 60.8183 75.0765C60.7847 75.1351 60.7512 75.1936 60.7176 75.2521L60.5854 75.5846L60.5161 75.7665L60.4719 75.9861L60.5029 76.3187C60.5112 76.3857 60.5048 76.4714 60.4837 76.576C60.4585 76.7015 60.5002 76.8187 60.6088 76.9276C60.684 76.9863 60.7384 77.0407 60.7718 77.091L60.7968 77.1287L60.7341 77.116C60.5919 77.0656 60.4686 76.9755 60.3642 76.8457C60.3517 76.7997 60.3203 76.7934 60.27 76.8268L60.2511 76.9209L60.389 77.0466L60.5269 77.1722L60.5583 77.1786C60.5583 77.1786 60.5478 77.1765 60.5269 77.1722C60.5269 77.1722 60.5248 77.1827 60.5206 77.2036C60.4997 77.1994 60.4641 77.214 60.4138 77.2474L60.464 77.3228C60.4597 77.3437 60.4576 77.3542 60.4576 77.3542C60.4786 77.3584 60.4765 77.3688 60.4513 77.3855L60.4764 77.4232C60.514 77.4525 60.6101 77.5154 60.7648 77.6119C60.8234 77.6454 60.8923 77.681 60.9718 77.7188C61.0721 77.7608 61.139 77.8069 61.1724 77.8571C61.2143 77.8655 61.2435 77.8823 61.2602 77.9074C61.2811 77.9117 61.3021 77.9159 61.323 77.9201C61.3481 77.9034 61.3586 77.9055 61.3543 77.9264C61.4463 78.0102 61.5529 78.0752 61.6742 78.1213C61.8163 78.1717 61.9083 78.2011 61.9502 78.2096L62.2199 78.3291L62.4081 78.367C62.4499 78.3754 62.4772 78.3483 62.4898 78.2855L62.4961 78.2542L62.5275 78.2605C62.5525 78.3526 62.5859 78.4028 62.6277 78.4112C62.6946 78.403 62.7386 78.4009 62.7595 78.4051L62.8222 78.4178L62.9227 78.4053C62.9478 78.3886 62.9917 78.3866 63.0545 78.3992C63.159 78.4203 63.2343 78.4246 63.2804 78.4121C63.3055 78.3954 63.3369 78.4017 63.3745 78.431C63.4372 78.4436 63.4791 78.4521 63.5 78.4563L63.845 78.5257L63.8764 78.5321L63.9455 78.5133C64.004 78.5469 64.1002 78.5554 64.2341 78.5388C64.3178 78.5556 64.4266 78.5558 64.5605 78.5392C64.6107 78.5058 64.6777 78.4975 64.7613 78.5144L65.3136 78.5276L65.3449 78.5339L65.4077 78.5466C65.4704 78.5592 65.5164 78.5467 65.5458 78.5091C65.6002 78.4548 65.64 78.4192 65.6652 78.4025L66.0359 78.0202C66.0652 77.9826 66.2161 77.828 66.4884 77.5564L66.7648 77.3182C67.0914 77.1011 67.2547 76.9925 67.2547 76.9925C67.305 76.9591 67.3636 76.9383 67.4305 76.93C67.5017 76.9008 67.5624 76.8695 67.6126 76.8361L67.6754 76.8487C67.6921 76.8738 67.7339 76.8823 67.8008 76.874L67.8322 76.8803C67.8322 76.8803 67.8301 76.8908 67.8259 76.9117C67.8259 76.9117 67.8154 76.9096 67.7945 76.9054L67.5558 77.1184C67.4804 77.1685 67.4113 77.2417 67.3484 77.3378C67.3484 77.3378 67.3442 77.3587 67.3358 77.4006L67.4048 77.3818C67.5137 77.2732 67.6038 77.2043 67.6749 77.1751C67.6749 77.1751 67.8131 77.0832 68.0895 76.8995L68.1209 76.9058C68.1586 76.8263 68.211 76.7825 68.2779 76.7742C68.3658 76.7701 68.4223 76.7597 68.4474 76.743C68.5395 76.718 68.596 76.7076 68.6169 76.7119C68.642 76.6951 68.6525 76.6973 68.6483 76.7182C68.6692 76.7224 68.6901 76.7266 68.711 76.7308C68.6608 76.7642 68.6356 76.7809 68.6356 76.7809C68.5436 76.8059 68.4662 76.8121 68.4034 76.7994L68.2967 76.8432C68.2715 76.8599 68.2548 76.8892 68.2464 76.931L68.3405 76.95L68.3781 76.9249L68.3718 76.9563C68.3676 76.9772 68.3822 77.0128 68.4156 77.063L68.5725 77.0946L68.7104 77.2203C68.844 77.4213 68.9736 77.5344 69.099 77.5597C69.1618 77.5723 69.2517 77.6122 69.3688 77.6793C69.3855 77.7044 69.3896 77.7379 69.3812 77.7797C69.3937 77.8257 69.3874 77.8571 69.3622 77.8738C69.358 77.8947 69.3434 77.9135 69.3182 77.9302C69.314 77.9511 69.3182 77.9846 69.3307 78.0307C69.3683 78.06 69.3808 78.106 69.3681 78.1688C69.3848 78.1939 69.3806 78.2148 69.3555 78.2315C69.3555 78.2315 69.345 78.2294 69.3241 78.2252C69.2781 78.2377 69.2362 78.2837 69.1984 78.3631C69.1607 78.4426 69.1397 78.4927 69.1355 78.5136C69.1146 78.5094 69.102 78.5178 69.0978 78.5387C69.1145 78.5638 69.1333 78.5785 69.1542 78.5827C69.1542 78.5827 69.1751 78.5869 69.217 78.5953L69.286 78.5766L69.2797 78.608L69.4808 78.4199C69.531 78.3865 69.5729 78.395 69.6063 78.4452C69.6105 78.4243 69.6126 78.4138 69.6126 78.4138C69.6335 78.418 69.6439 78.4202 69.6439 78.4202L69.7193 78.37C69.7109 78.4119 69.6962 78.4307 69.6753 78.4265C69.6669 78.4683 69.6501 78.4976 69.625 78.5143C69.5245 78.5811 69.4889 78.6501 69.518 78.7212L69.4804 78.7463C69.4552 78.763 69.4197 78.7776 69.3736 78.7901C69.3276 78.8026 69.2773 78.836 69.2229 78.8903L69.1224 78.9027L69.0094 78.9779C69.0052 78.9988 68.9884 79.0281 68.9591 79.0657C68.9297 79.1033 68.8984 79.097 68.865 79.0467C68.844 79.0425 68.821 79.0488 68.7959 79.0655C68.7917 79.0864 68.7896 79.0968 68.7896 79.0968C68.777 79.1596 68.7518 79.1763 68.7142 79.147C68.7142 79.147 68.7038 79.1449 68.6828 79.1406C68.6619 79.1364 68.6494 79.1448 68.6452 79.1657L68.6262 79.2598L68.6953 79.2411C68.7162 79.2453 68.7287 79.2369 68.733 79.216L68.7517 79.2851L68.714 79.3101C68.6805 79.3687 68.6951 79.4042 68.7578 79.4169L68.8896 79.4108C68.8393 79.4442 68.8121 79.4713 68.8079 79.4922C68.7241 79.5842 68.6153 79.6384 68.4814 79.655C68.4814 79.655 68.4437 79.68 68.3683 79.7302L68.2363 79.8994L68.1736 79.8868C68.1359 79.8575 68.0878 79.8804 68.0291 79.9557L67.6959 80.4761L67.4255 80.846L67.3815 80.9025C67.3229 80.9777 67.3207 81.0425 67.375 81.097C67.4126 81.1263 67.4566 81.1243 67.5068 81.0909L67.8584 80.9658L67.9211 80.9785C67.9546 81.0287 67.988 81.0246 68.0216 80.966C68.0258 80.9451 68.0383 80.9368 68.0593 80.941C68.0802 80.9452 68.0927 80.9368 68.0969 80.9159C68.189 80.8909 68.2602 80.8617 68.3104 80.8283C68.3104 80.8283 68.3356 80.8116 68.3858 80.7782C68.3816 80.7991 68.3795 80.8096 68.3795 80.8096C68.4004 80.8138 68.4109 80.8159 68.4109 80.8159C68.3606 80.8493 68.3334 80.8765 68.3292 80.8974C68.304 80.9141 68.2664 80.9392 68.2161 80.9726C68.1701 80.9851 68.1324 81.0101 68.1031 81.0477L68.0654 81.0728L67.7704 81.0787C67.7495 81.0745 67.7369 81.0828 67.7327 81.1037C67.7285 81.1246 67.7138 81.1435 67.6887 81.1602C67.6175 81.1894 67.4941 81.208 67.3184 81.2162C67.2556 81.2035 67.1949 81.2348 67.1363 81.3101L66.5767 82.144C66.3838 82.4534 66.2287 82.6833 66.1114 82.8338L65.7781 83.3542C65.7194 83.4295 65.6859 83.488 65.6775 83.5298C65.493 83.7974 65.3631 84.0106 65.2876 84.1695C65.2582 84.2071 65.2163 84.253 65.1619 84.3074C65.1074 84.3617 65.0655 84.4076 65.0362 84.4453L64.7406 84.9407L64.5075 85.6119L64.3376 85.9694C64.325 86.0321 64.2999 86.0488 64.2623 86.0195L64.2183 86.0759L64.1677 86.3269C64.1551 86.3896 64.1321 86.3959 64.0987 86.3456C64.0987 86.3456 64.0882 86.3435 64.0673 86.3393C64.0673 86.3393 64.0652 86.3498 64.061 86.3707C64.0484 86.4334 64.0525 86.4669 64.0734 86.4711C64.1362 86.4837 64.1424 86.5068 64.0922 86.5402C64.0628 86.5778 64.0461 86.607 64.0418 86.628C64.0334 86.6698 64.0271 86.7012 64.0229 86.7221C64.0312 86.789 64.0039 86.8162 63.9412 86.8035L63.8471 86.7846C63.8053 86.7762 63.7718 86.7803 63.7467 86.797C63.7173 86.8346 63.6985 86.8744 63.69 86.9162C63.6858 86.9371 63.6712 86.9559 63.646 86.9726C63.6209 86.9893 63.6083 86.9977 63.6083 86.9977C63.5498 86.9641 63.5059 86.9662 63.4765 87.0038C63.4472 87.0414 63.4304 87.0707 63.4262 87.0916L63.4199 87.1229C63.3906 87.1606 63.3968 87.1836 63.4387 87.192L63.4951 87.236L63.4574 87.2611C63.3653 87.286 63.3088 87.2964 63.2879 87.2922C63.2378 87.2168 63.2149 87.1687 63.2191 87.1478C63.2317 87.0851 63.215 87.0599 63.169 87.0724L63.0999 87.0912L63.0245 87.1413L63.106 87.223C63.1269 87.2272 63.1353 87.2397 63.1311 87.2606L63.062 87.2794L62.9428 87.2228L62.9555 87.16L62.9681 87.0973C62.9054 87.0846 62.8719 87.0888 62.8677 87.1097C62.8341 87.1682 62.786 87.1912 62.7232 87.1785C62.6563 87.1868 62.6291 87.214 62.6416 87.26C62.6625 87.2642 62.6729 87.2663 62.6729 87.2663C62.6687 87.2873 62.6562 87.2956 62.6352 87.2914C62.631 87.3123 62.5954 87.3269 62.5285 87.3352C62.4782 87.3686 62.4448 87.3727 62.4281 87.3476L62.334 87.3287ZM62.9361 87.5805C62.9152 87.5762 62.888 87.549 62.8546 87.4988L62.8609 87.4674L62.9738 87.5554C62.9696 87.5763 62.957 87.5847 62.9361 87.5805ZM62.2794 85.8161C62.3212 85.8246 62.3547 85.8204 62.3798 85.8037L62.3861 85.7724C62.3903 85.7514 62.3715 85.7368 62.3297 85.7283C62.2879 85.7199 62.2816 85.6969 62.311 85.6593L62.3487 85.6342L62.2859 85.6216L62.2545 85.6153C62.267 85.6613 62.2524 85.6801 62.2105 85.6717C62.1603 85.7051 62.1352 85.7218 62.1352 85.7218L62.2167 85.8035L62.2794 85.8161ZM61.9225 85.1567L61.9415 85.0626C61.9499 85.0208 61.9667 84.9915 61.9918 84.9748C61.9918 84.9748 61.9939 84.9644 61.9981 84.9435C61.9981 84.9435 62.0086 84.9456 62.0295 84.9498L62.0232 84.9811L61.9539 85.1631C61.9497 85.184 61.9371 85.1923 61.9162 85.1881L61.9225 85.1567ZM62.5434 85.4776C62.5685 85.4609 62.5748 85.4295 62.5624 85.3835C62.5666 85.3626 62.5708 85.3417 62.575 85.3207L62.4807 85.465L62.4994 85.534L62.5434 85.4776ZM63.17 86.2566L63.1262 86.1498C63.0759 86.1832 63.0508 86.1999 63.0508 86.1999L63.126 86.313L63.17 86.2566ZM62.3369 85.0443L62.3809 84.9879C62.3767 85.0088 62.3745 85.0192 62.3745 85.0192C62.3912 85.0444 62.3975 85.0674 62.3933 85.0883L62.3556 85.1134L62.3369 85.0443ZM63.3268 86.2882L63.2767 86.2128L63.2014 86.2629C63.1971 86.2838 63.195 86.2943 63.195 86.2943C63.2117 86.3194 63.2222 86.3215 63.2264 86.3006L63.3268 86.2882ZM63.1639 86.1248C63.1848 86.129 63.1974 86.1206 63.2016 86.0997L63.1828 86.0307L63.1388 86.0871C63.1346 86.108 63.1325 86.1185 63.1325 86.1185C63.1534 86.1227 63.1639 86.1248 63.1639 86.1248ZM58.8363 79.0842L58.8426 79.0528L58.7548 79.0025L58.7298 78.9648L58.6858 79.0212L58.7986 79.1093L58.8363 79.0842ZM63.4028 85.7485L63.3464 85.7045C63.3213 85.7212 63.2983 85.7275 63.2774 85.7233C63.2564 85.7191 63.2439 85.7274 63.2397 85.7483C63.2312 85.7902 63.2689 85.8195 63.3525 85.8363L63.4028 85.7485ZM58.0409 77.8469C58.0451 77.826 58.0576 77.8176 58.0785 77.8218L57.9846 77.6397L57.9533 77.6334L57.947 77.6648L58.0158 77.8092C58.0116 77.8301 58.0095 77.8406 58.0095 77.8406C58.0304 77.8448 58.0409 77.8469 58.0409 77.8469ZM58.4419 78.2867C58.3544 78.0732 58.3022 77.9539 58.2855 77.9288C58.2354 77.8534 58.2103 77.8157 58.2103 77.8157L58.1977 77.8784L58.4043 78.3117L58.4356 78.318L58.4419 78.2867ZM62.6386 84.6807C62.6176 84.6765 62.5905 84.6493 62.5571 84.599L62.6891 84.4297C62.6933 84.4088 62.7163 84.4026 62.7581 84.411C62.7497 84.4528 62.7664 84.4779 62.8082 84.4864L62.7392 84.5051L62.6828 84.4611C62.6743 84.5029 62.6806 84.5259 62.7015 84.5302C62.7223 84.6431 62.7013 84.6933 62.6386 84.6807ZM63.4658 85.598L63.447 85.5289C63.4428 85.5499 63.4303 85.5582 63.4094 85.554L63.3277 85.6355C63.3068 85.6313 63.2942 85.6396 63.29 85.6605L63.3214 85.6669L63.4658 85.598ZM63.4346 85.4285C63.4388 85.4076 63.4305 85.395 63.4096 85.3908L63.3279 85.4723C63.3488 85.4765 63.3571 85.4891 63.3529 85.51L63.4346 85.4285ZM58.831 78.2997L58.7121 78.0799C58.7163 78.059 58.7079 78.0464 58.687 78.0422L58.6493 78.0673L58.7997 78.2934L58.831 78.2997ZM59.2182 79.7813C59.2349 79.8064 59.2538 79.8211 59.2747 79.8253C59.3207 79.8128 59.3542 79.8087 59.3751 79.8129L59.3814 79.7815L59.4191 79.7564C59.4149 79.7774 59.4337 79.792 59.4755 79.8004C59.4797 79.7795 59.4923 79.7712 59.5132 79.7754L59.9337 79.7947L59.9964 79.8074L59.94 79.7634L59.8772 79.7507C59.8563 79.7465 59.8333 79.7528 59.8082 79.7695C59.8082 79.7695 59.7998 79.7569 59.7831 79.7318C59.7204 79.7192 59.7141 79.6961 59.7644 79.6627C59.6976 79.5622 59.6642 79.512 59.6642 79.512C59.6726 79.4702 59.6559 79.445 59.614 79.4366C59.6768 79.4493 59.7061 79.466 59.7018 79.4869C59.7228 79.4912 59.7499 79.5184 59.7833 79.5686C59.867 79.5855 59.9318 79.5876 59.9779 79.5752L59.9715 79.6065L60.028 79.6505L60.0406 79.5878C60.0073 79.4288 59.9405 79.3283 59.8402 79.2863L59.5016 79.0223C59.4431 78.9887 59.3971 78.9468 59.3637 78.8966C59.3345 78.8254 59.3011 78.7752 59.2635 78.7458C59.2468 78.7207 59.2175 78.704 59.1757 78.6955L59.1631 78.7583C59.1002 78.8544 59.0938 78.9402 59.1439 79.0156C59.1731 79.0867 59.242 79.1768 59.3507 79.2857L59.5576 79.3926L59.4572 79.405C59.4154 79.3966 59.3902 79.4133 59.3818 79.4552C59.4152 79.5054 59.4319 79.5305 59.4319 79.5305L59.6138 79.5998L59.664 79.6752L59.5258 79.7126L59.4193 79.5933L59.2938 79.568L59.3062 79.6684L59.3313 79.7061L59.2999 79.6998L59.2498 79.6244C59.2289 79.6202 59.1996 79.6035 59.162 79.5741C59.1453 79.549 59.1265 79.5343 59.1056 79.5301C59.0429 79.5175 58.9885 79.5174 58.9424 79.5299L58.9047 79.555L58.9612 79.599C58.9863 79.5823 58.9967 79.5844 58.9925 79.6053C59.0135 79.6095 59.0344 79.6137 59.0553 79.6179C59.0887 79.6682 59.143 79.7226 59.2182 79.7813ZM58.0606 77.1001C58.0439 77.075 58.0419 77.031 58.0545 76.9683L57.9981 76.9243L57.9855 76.987C58.0189 77.0373 58.0335 77.0729 58.0293 77.0938L58.0606 77.1001ZM58.4179 77.4331C58.4306 77.3704 58.4285 77.3265 58.4118 77.3014L58.4181 77.27L58.4495 77.2763L58.5057 77.4835L58.468 77.5085L58.4179 77.4331ZM63.6233 85.1401L63.6172 85.0083L63.5858 85.002L63.5795 85.0333C63.571 85.0752 63.5752 85.1086 63.5919 85.1338L63.5605 85.1274C63.5814 85.1317 63.5919 85.1338 63.5919 85.1338C63.5877 85.1547 63.5856 85.1651 63.5856 85.1651L63.6233 85.1401ZM63.4666 84.9453C63.5378 84.9161 63.5671 84.8785 63.5546 84.8325L63.4416 84.9076L63.4666 84.9453ZM59.1011 78.093L58.9883 78.005L58.9569 77.9986L59.0321 78.1117L59.1011 78.093ZM58.6935 77.8477C58.6768 77.8226 58.6476 77.7514 58.6059 77.6342C58.5935 77.5882 58.581 77.5421 58.5685 77.4961C58.5602 77.4291 58.5393 77.3705 58.5059 77.3203C58.4725 77.27 58.4664 77.1926 58.4874 77.0881C58.4875 76.9793 58.4605 76.8977 58.4061 76.8432C58.3894 76.8181 58.3706 76.8034 58.3497 76.7992C58.3497 76.7992 58.3476 76.8097 58.3434 76.8306C58.3393 76.7427 58.3123 76.6067 58.2623 76.4226C58.2413 76.5271 58.2473 76.7133 58.2804 76.9811C58.2762 77.002 58.3117 77.0962 58.3868 77.2637C58.3699 77.3473 58.3699 77.4017 58.3866 77.4268L58.6559 77.8728C58.6768 77.877 58.6851 77.8895 58.6809 77.9104L58.6935 77.8477ZM58.3493 77.1256L58.3556 77.0942L58.3434 76.8306L58.4183 77.1068L58.4057 77.1696L58.3493 77.1256ZM59.4584 78.426L59.5024 78.3696L59.3896 78.2816L59.3456 78.338C59.3163 78.3756 59.3225 78.3987 59.3643 78.4071C59.4104 78.3946 59.4313 78.3988 59.4271 78.4197L59.4584 78.426ZM59.9785 79.0856C59.9284 79.0103 59.8929 78.9705 59.872 78.9663C59.872 78.9663 59.851 78.9621 59.8092 78.9536L59.8029 78.985L59.8343 78.9913C59.851 79.0165 59.8698 79.0311 59.8907 79.0353C59.9325 79.0438 59.9618 79.0605 59.9785 79.0856ZM59.7469 78.6147C59.6632 78.5978 59.613 78.5768 59.5963 78.5517L59.5589 78.4136L59.7595 78.5519C59.8013 78.5604 59.8201 78.575 59.8159 78.5959L59.7469 78.6147ZM58.3941 76.4165C58.3983 76.3955 58.4004 76.3851 58.4004 76.3851C58.4256 76.3684 58.4402 76.3496 58.4444 76.3287L58.4006 76.2219L58.3756 76.1842L58.3693 76.2156C58.3566 76.2783 58.3587 76.3223 58.3754 76.3474L58.3941 76.4165ZM60.2423 78.9103L60.2486 78.8789C60.2695 78.8831 60.3135 78.8811 60.3804 78.8728C60.4725 78.8478 60.5457 78.8625 60.6 78.917C60.6 78.917 60.6105 78.9191 60.6314 78.9233C60.6565 78.9066 60.6586 78.8961 60.6377 78.8919C60.6461 78.8501 60.6315 78.8145 60.5939 78.7852C60.5772 78.7601 60.5563 78.7559 60.5311 78.7726C60.4851 78.7851 60.4412 78.7871 60.3993 78.7787C60.3617 78.7493 60.3304 78.743 60.3052 78.7597L60.3116 78.7284C60.3367 78.7117 60.3388 78.7012 60.3179 78.697C60.3012 78.6719 60.2928 78.6593 60.2928 78.6593L60.0231 78.5397C59.9395 78.5229 59.8182 78.4767 59.6593 78.4012L59.5589 78.4136C59.4835 78.4637 59.4834 78.5181 59.5587 78.5768L59.9412 78.7844L59.9726 78.7907C60.0144 78.7991 60.0291 78.7803 60.0166 78.7343L60.0669 78.6465L60.117 78.7218L60.2048 78.7721C60.2215 78.7973 60.2173 78.8182 60.1922 78.8349L60.1482 78.8913L60.2423 78.9103ZM63.1095 84.4491C63.1137 84.4282 63.1158 84.4177 63.1158 84.4177C63.1368 84.4219 63.1472 84.424 63.1472 84.424C63.273 84.2317 63.3568 84.0854 63.3988 83.9851C63.5204 83.8137 63.6818 83.5524 63.883 83.2012L63.8957 83.1385L63.8266 83.1572L63.5373 83.6212L63.3927 83.8533L63.1222 84.3864L63.1095 84.4491ZM59.0523 77.0386C59.1025 77.0052 59.1381 76.9906 59.159 76.9948L59.1026 76.9508L58.9523 76.7247L58.9335 76.6556L58.8958 76.6807L58.8895 76.712C58.9062 76.7372 58.9313 76.7749 58.9647 76.8251C59.0023 76.8544 59.0065 76.8879 58.9771 76.9255C58.9729 76.9464 58.9792 76.9695 58.9959 76.9946C59.0377 77.003 59.0565 77.0177 59.0523 77.0386ZM60.8821 79.137C60.8863 79.1161 60.8884 79.1056 60.8884 79.1056C60.9094 79.1098 60.9198 79.1119 60.9198 79.1119L60.832 79.0616L60.8006 79.0553L60.8821 79.137ZM58.6773 75.8206L58.7278 75.5697C58.7404 75.5069 58.7384 75.463 58.7217 75.4379L58.6903 75.4315L58.6524 75.6198L58.6459 75.8143L58.6647 75.8834L58.6773 75.8206ZM64.0833 83.6659L64.1586 83.6158L64.2151 83.6598C64.2108 83.6807 64.1878 83.6869 64.146 83.6785L64.0833 83.6659ZM61.3213 79.2254L61.2649 79.1814C61.2482 79.1563 61.2085 79.1374 61.1457 79.1248C61.1248 79.1206 61.1122 79.1289 61.108 79.1498L61.2523 79.2442L61.3213 79.2254ZM62.9246 81.8005C62.9288 81.7796 62.9205 81.767 62.8996 81.7628L62.9122 81.7001L62.9686 81.7441L62.9874 81.8131C62.9874 81.8131 62.9748 81.8215 62.9497 81.8382C62.9497 81.8382 62.9413 81.8256 62.9246 81.8005ZM59.1601 76.1789C59.0932 76.0785 59.0725 75.9655 59.0977 75.84L59.1041 75.8086C59.1457 75.9258 59.1644 76.0493 59.1601 76.1789ZM61.6405 79.9099L61.6154 79.8722C61.6197 79.8513 61.6218 79.8408 61.6218 79.8408C61.6427 79.845 61.6531 79.8471 61.6531 79.8471C61.7117 79.8807 61.7932 79.908 61.8978 79.929L61.9165 79.9981L61.8538 79.9855L61.6405 79.9099ZM63.3601 84.826L63.4607 84.6504L63.467 84.619C63.4294 84.5897 63.442 84.5813 63.5047 84.5939L63.5675 84.6066C63.5592 84.5396 63.5759 84.5104 63.6178 84.5188C63.6554 84.5481 63.6742 84.5628 63.6742 84.5628L63.7119 84.5377L63.6868 84.5L63.6241 84.4874L63.6681 84.431C63.6723 84.4101 63.6744 84.3996 63.6744 84.3996C63.6953 84.4038 63.7058 84.4059 63.7058 84.4059L63.7371 84.4122L63.8062 84.3935C63.8229 84.4186 63.8355 84.4103 63.8439 84.3684C63.8481 84.3475 63.8628 84.3287 63.8879 84.312C63.8419 84.3245 63.8105 84.3182 63.7938 84.2931C63.798 84.2722 63.8022 84.2512 63.8064 84.2303C63.7897 84.2052 63.8086 84.1655 63.863 84.1112C63.8673 84.0902 63.8798 84.0819 63.9007 84.0861L63.8944 84.1175C63.9153 84.1217 63.9258 84.1238 63.9258 84.1238C63.9216 84.1447 63.9195 84.1552 63.9195 84.1552L63.9258 84.1238C63.9929 84.0067 64.0704 83.9462 64.1582 83.9421C64.1791 83.9463 64.2147 83.9317 64.265 83.8983C64.2483 83.8732 64.219 83.8564 64.1772 83.848L64.1207 83.804L64.0643 83.76C64.1061 83.7684 64.1292 83.7622 64.1334 83.7412C64.1543 83.7454 64.1899 83.7309 64.2401 83.6974C64.2904 83.664 64.328 83.639 64.3532 83.6223L64.3658 83.5595C64.3658 83.5595 64.3575 83.547 64.3407 83.5219C64.3407 83.5219 64.3512 83.524 64.3721 83.5282C64.3805 83.4863 64.3743 83.4633 64.3534 83.4591C64.2906 83.4465 64.2551 83.4611 64.2466 83.5029L64.2026 83.5593L64.1839 83.4903L64.2279 83.4338C64.2991 83.4047 64.3221 83.344 64.2972 83.2519L64.3161 83.1578C64.3579 83.1662 64.3852 83.1391 64.3978 83.0763L64.4921 82.9321C64.5172 82.9154 64.534 82.8862 64.5424 82.8443C64.5509 82.8025 64.5467 82.769 64.53 82.7439L64.5363 82.7125C64.5824 82.7 64.6159 82.6415 64.637 82.5369C64.6747 82.4575 64.7166 82.4115 64.7626 82.399L64.769 82.3677C64.7774 82.3258 64.8151 82.2464 64.8822 82.1293L64.8635 82.0603L64.8698 82.0289L64.9325 82.0415C65.0246 82.0165 65.0561 81.9685 65.0269 81.8973L65.0081 81.8283L65.0208 81.7655L64.9831 81.7906C64.9286 81.8449 64.8678 81.9306 64.8008 82.0476L64.5555 82.4553L64.4172 82.6559C64.3878 82.6935 64.3647 82.7542 64.3479 82.8378C64.3186 82.8754 64.2767 82.9214 64.2222 82.9757C64.1887 83.0342 64.1677 83.0844 64.1593 83.1263C64.1717 83.1723 64.1529 83.212 64.1026 83.2454C64.0691 83.3039 64.0481 83.3541 64.0397 83.396C64.0228 83.4796 63.96 83.5758 63.851 83.6844C63.8008 83.7178 63.7924 83.7596 63.8258 83.8099L63.7818 83.8663C63.7315 83.8997 63.7022 83.9373 63.6938 83.9792C63.6729 83.9749 63.6561 84.0042 63.6435 84.067C63.6392 84.0879 63.6267 84.0962 63.6058 84.092L63.6622 84.136L63.6936 84.1423L63.6559 84.1674L63.5868 84.1861L63.5805 84.2175C63.639 84.251 63.6306 84.2929 63.5552 84.343C63.5468 84.3848 63.53 84.4141 63.5049 84.4308C63.4965 84.4726 63.4714 84.4893 63.4296 84.4809C63.3835 84.4934 63.3563 84.5205 63.3479 84.5624C63.3394 84.6042 63.3331 84.6356 63.3289 84.6565C63.3289 84.6565 63.3268 84.6669 63.3226 84.6878C63.3351 84.7339 63.3183 84.7631 63.2723 84.7756L63.2597 84.8384L63.291 84.8447L63.3601 84.826ZM59.8121 76.6693L59.7182 76.4872C59.7182 76.4872 59.7078 76.4851 59.6868 76.4809C59.6868 76.4809 59.6847 76.4913 59.6805 76.5122C59.6805 76.5122 59.668 76.5206 59.6428 76.5373C59.6428 76.5373 59.6533 76.5394 59.6742 76.5436L59.7494 76.6567C59.7452 76.6776 59.7431 76.688 59.7431 76.688C59.764 76.6922 59.7765 76.6839 59.7807 76.663L59.8121 76.6693ZM61.8228 79.6528C61.8437 79.657 61.8563 79.6487 61.8605 79.6278C61.8605 79.6278 61.8501 79.6256 61.8291 79.6214C61.8291 79.6214 61.8312 79.611 61.8355 79.5901L61.8041 79.5837L61.7477 79.5397L61.735 79.6025C61.7517 79.6276 61.781 79.6444 61.8228 79.6528ZM60.8208 77.9822C60.825 77.9613 60.8167 77.9487 60.7958 77.9445L60.6766 77.8879L60.6703 77.9192L60.7831 78.0072L60.8208 77.9822ZM58.9859 74.9361C58.9859 74.9361 58.9755 74.934 58.9545 74.9298C58.9545 74.9298 58.9567 74.9194 58.9609 74.8984C58.8769 75.0992 58.8077 75.2267 58.7533 75.281L58.7847 75.2873L58.9859 74.9361ZM60.1631 77.0337C60.2133 77.0003 60.2385 76.9836 60.2385 76.9836L60.182 76.9396C60.182 76.9396 60.1716 76.9375 60.1507 76.9333C60.1507 76.9333 60.1486 76.9438 60.1444 76.9647L60.1631 77.0337ZM59.6799 77.0017L59.6612 76.9327L59.4607 76.6312C59.3814 76.4846 59.3356 76.334 59.3232 76.1792C59.3109 76.0243 59.3089 75.926 59.3173 75.8842C59.3257 75.8424 59.3404 75.8236 59.3613 75.8278C59.3865 75.8111 59.3907 75.7901 59.374 75.765L59.3552 75.696C59.3721 75.6123 59.3387 75.5621 59.255 75.5452C59.2341 75.541 59.2153 75.5263 59.1986 75.5012C59.1819 75.4761 59.1756 75.4531 59.1798 75.4322C59.2385 75.3569 59.2847 75.2357 59.3184 75.0683C59.373 74.9052 59.4191 74.784 59.4569 74.7045L59.4632 74.6732C59.4423 74.6689 59.4297 74.6773 59.4255 74.6982L59.3375 74.8111C59.2286 74.9197 59.1699 74.9949 59.1615 75.0368C59.0776 75.2375 59.0251 75.3901 59.004 75.4947L58.9723 75.8147C58.9678 76.0532 59.0114 76.2687 59.1032 76.4613C59.2368 76.6623 59.3037 76.7628 59.3037 76.7628C59.3455 76.7712 59.3685 76.7649 59.3727 76.744L59.4041 76.7503C59.425 76.7546 59.4334 76.7671 59.4291 76.788C59.4501 76.7922 59.448 76.8027 59.4228 76.8194L59.4102 76.8821C59.4729 76.8948 59.5419 76.9304 59.6172 76.9891L59.6799 77.0017ZM59.1051 74.9928L59.0737 74.9865L58.9354 75.1871C58.9563 75.1913 58.9647 75.2039 58.9605 75.2248L59.1051 74.9928ZM59.5428 76.2234C59.547 76.2025 59.5596 76.1941 59.5805 76.1983L59.5243 75.9911L59.5186 75.533L59.5312 75.4703L59.4872 75.5267C59.4954 75.7024 59.491 75.8321 59.4742 75.9158C59.4992 76.0078 59.5053 76.0853 59.4927 76.148L59.5428 76.2234ZM63.0695 81.4053C63.0946 81.3886 63.1281 81.3845 63.1699 81.3929C63.2117 81.4013 63.241 81.4181 63.2577 81.4432C63.2953 81.4725 63.3204 81.4558 63.3331 81.3931L63.3708 81.368L63.6343 81.3558L63.6657 81.3621C63.6699 81.3412 63.6616 81.3287 63.6407 81.3245C63.6449 81.3035 63.6261 81.2889 63.5842 81.2805L63.1261 81.2862L62.9252 81.311L62.8876 81.3361C62.9252 81.3654 62.944 81.3801 62.944 81.3801L63.0695 81.4053ZM64.2666 82.593C64.2666 82.593 64.2562 82.5908 64.2353 82.5866C64.2353 82.5866 64.2374 82.5762 64.2416 82.5553C64.2416 82.5553 64.2311 82.5532 64.2102 82.5489C64.2102 82.5489 64.2081 82.5594 64.2039 82.5803C64.1788 82.597 64.1641 82.6158 64.1599 82.6367C64.1515 82.6786 64.1347 82.7078 64.1096 82.7245L64.1346 82.7622L64.2666 82.593ZM62.9075 80.4261C62.9285 80.4303 62.941 80.422 62.9452 80.401C62.9704 80.3843 63.0247 80.3844 63.1084 80.4013C63.2339 80.4265 63.3301 80.435 63.397 80.4267L64.2506 80.4027C64.2924 80.4111 64.3217 80.4279 64.3384 80.453L64.1752 80.4528C64.1543 80.4486 64.1396 80.4674 64.1312 80.5092L64.1939 80.5219L64.3447 80.4217C64.3656 80.4259 64.3782 80.4175 64.3824 80.3966L64.3573 80.3589L64.2946 80.3463C64.0854 80.3042 63.9307 80.2621 63.8303 80.2202L63.7049 80.1949L63.5794 80.1696C63.433 80.1402 63.3222 80.0961 63.2469 80.0374L63.2156 80.0311C63.1946 80.0269 63.1466 79.9955 63.0713 79.9368L63.0463 79.8991L63.0777 79.9054L63.2094 79.8993C63.2304 79.9035 63.2534 79.8973 63.2785 79.8806C63.3036 79.8639 63.2974 79.8409 63.2598 79.8115C63.2849 79.7948 63.3184 79.7907 63.3602 79.7991C63.402 79.8075 63.4313 79.8243 63.448 79.8494C63.4647 79.8745 63.5044 79.8934 63.5672 79.9061C63.609 79.9145 63.6132 79.8936 63.5798 79.8433L63.6112 79.8496L63.6676 79.8936L63.699 79.8999C63.699 79.8999 63.7241 79.8832 63.7743 79.8498C63.7743 79.8498 63.791 79.875 63.8244 79.9252L63.9122 79.9755L64.0063 79.9945L64.0754 79.9757L64.0817 79.9444L63.9876 79.9254C63.9876 79.9254 63.9771 79.9233 63.9562 79.9191C63.9562 79.9191 63.9541 79.9296 63.9499 79.9505C63.9499 79.9505 63.9395 79.9484 63.9185 79.9442C63.9185 79.9442 63.9207 79.9337 63.9249 79.9128C63.9333 79.871 63.9501 79.8417 63.9752 79.825L64.0693 79.8439L64.1007 79.8502C64.1216 79.8545 64.1425 79.8587 64.1634 79.8629C64.2094 79.8504 64.2387 79.8672 64.2512 79.9132L64.3203 79.8945L64.3579 79.8694L64.5085 79.9324C64.5378 79.8947 64.5817 79.8927 64.6403 79.9262L64.747 79.8824C64.7721 79.8657 64.7889 79.8365 64.7973 79.7947C64.8015 79.7737 64.7827 79.7591 64.7409 79.7507L64.264 79.6873L64.1699 79.6683C64.0947 79.6097 64.0362 79.5761 63.9943 79.5677L63.8625 79.5738L63.6493 79.4982C63.6283 79.494 63.6158 79.5024 63.6116 79.5233C63.6074 79.5442 63.5927 79.563 63.5676 79.5797C63.5342 79.5295 63.5175 79.5043 63.5175 79.5043C63.4798 79.475 63.4276 79.4645 63.3606 79.4728C63.3188 79.4643 63.2791 79.4455 63.2414 79.4161L62.545 79.3086L62.3881 79.277L62.2313 79.2454C62.2061 79.2621 62.1831 79.2684 62.1622 79.2641C62.1664 79.2432 62.156 79.2411 62.1308 79.2578C62.0806 79.2912 62.0471 79.2954 62.0304 79.2703C62.0137 79.2451 61.974 79.2262 61.9112 79.2136L61.9049 79.245L61.8923 79.3077L61.8609 79.3014C61.84 79.2972 61.8296 79.2951 61.8296 79.2951C61.8338 79.2742 61.8359 79.2637 61.8359 79.2637C61.8401 79.2428 61.8317 79.2303 61.8108 79.226L61.5723 79.2759C61.5304 79.2675 61.5116 79.2529 61.5159 79.2319C61.541 79.2152 61.5222 79.2006 61.4594 79.1879L61.4217 79.213C61.3799 79.2046 61.3569 79.2108 61.3527 79.2317C61.3485 79.2526 61.3443 79.2736 61.3401 79.2945C61.3316 79.3363 61.3525 79.3405 61.4028 79.3071C61.4028 79.3071 61.4007 79.3176 61.3965 79.3385C61.3965 79.3385 61.4069 79.3406 61.4278 79.3448L61.4529 79.3825C61.4738 79.3867 61.5052 79.393 61.547 79.4014C61.5931 79.3889 61.6453 79.3995 61.7039 79.433L61.9171 79.5086L61.9045 79.5713C61.8794 79.588 61.8752 79.6089 61.8919 79.6341C61.9128 79.6383 61.9211 79.6508 61.9169 79.6718L61.9797 79.6844C61.9797 79.6844 61.9692 79.6823 61.9483 79.6781C61.9483 79.6781 61.9504 79.6676 61.9546 79.6467L61.9609 79.6153L62.0675 79.7347L61.9984 79.7534L61.4714 79.6147L61.3209 79.5518C61.3 79.5475 61.2561 79.5496 61.1891 79.5579C61.1473 79.5494 61.118 79.5327 61.1013 79.5075L60.7752 79.344C60.7752 79.344 60.7647 79.3419 60.7438 79.3376C60.7438 79.3376 60.7459 79.3272 60.7501 79.3063L60.8505 79.2939L60.9697 79.3505C61.02 79.3171 61.0388 79.3317 61.0261 79.3945L61.1139 79.4448L61.1643 79.357L61.1015 79.3444L61.0765 79.3067L60.9322 79.2124L60.6375 79.0551C60.6166 79.0509 60.5726 79.0529 60.5057 79.0612C60.4639 79.0528 60.4262 79.0235 60.3928 78.9732L60.3362 79.0924L60.3926 79.1364C60.4511 79.1699 60.5432 79.1993 60.6686 79.2246L60.7251 79.2686L60.656 79.2873L60.5055 79.2244L60.4741 79.2181L60.4678 79.2494L60.5493 79.3311C60.5702 79.3353 60.5785 79.3479 60.5743 79.3688L60.5116 79.3562C60.4488 79.3435 60.3798 79.3079 60.3046 79.2492L60.2732 79.2429L60.2669 79.2743C60.3045 79.3036 60.3714 79.3497 60.4676 79.4126C60.5637 79.4755 60.6662 79.507 60.775 79.5071L60.7687 79.5385C60.7687 79.5385 60.7665 79.549 60.7623 79.5699C60.7623 79.5699 60.7728 79.572 60.7937 79.5762L60.8878 79.5951C60.9506 79.6078 60.9882 79.6371 61.0007 79.6831C60.9965 79.7041 60.9944 79.7145 60.9944 79.7145C61.0153 79.7187 61.0257 79.7208 61.0257 79.7208C61.1428 79.7879 61.2327 79.8278 61.2954 79.8404C61.333 79.8697 61.4041 79.8949 61.5087 79.916L61.5024 79.9474L61.5588 79.9914L61.6843 80.0166C61.7428 80.0502 61.8348 80.0796 61.9603 80.1048C62.2615 80.122 62.4895 80.1243 62.6444 80.112C62.7071 80.1246 62.8054 80.1226 62.9393 80.1061C62.8891 80.1395 62.864 80.1562 62.864 80.1562L62.4686 80.1745C62.4476 80.1703 62.4351 80.1787 62.4309 80.1996C62.5479 80.2667 62.6378 80.3065 62.7006 80.3191C62.7215 80.3234 62.7529 80.3297 62.7947 80.3381C62.8574 80.3507 62.8951 80.3801 62.9075 80.4261ZM62.1374 79.0633C62.1583 79.0675 62.1708 79.0591 62.175 79.0382L62.15 79.0005L62.0496 79.013L62.106 79.057L62.1374 79.0633ZM64.3359 82.411L64.4489 82.3359L64.4302 82.2668C64.4093 82.2626 64.3967 82.271 64.3925 82.2919L64.3108 82.3734L64.3045 82.4047L64.3359 82.411ZM62.4761 79.1641C62.4845 79.1223 62.4783 79.0993 62.4574 79.0951C62.4616 79.0742 62.4428 79.0595 62.401 79.0511L62.3696 79.0448C62.3989 79.0071 62.3927 78.9841 62.3508 78.9757C62.3299 78.9715 62.3195 78.9694 62.3195 78.9694L62.4826 78.9696L62.2631 78.9254L62.194 78.9441C62.2149 78.9483 62.2233 78.9609 62.2191 78.9818C62.24 78.986 62.2379 78.9965 62.2127 79.0132C62.2127 79.0132 62.2232 79.0153 62.2441 79.0195C62.2357 79.0613 62.2524 79.0864 62.2942 79.0949C62.3109 79.12 62.3506 79.1389 62.4134 79.1515L62.4761 79.1641ZM64.2797 82.2039C64.3048 82.1872 64.3425 82.1621 64.3927 82.1287C64.4681 82.0786 64.5016 82.0201 64.4934 81.9531L64.4997 81.9217L64.4306 81.9405L64.2797 82.2039ZM62.6275 78.5744L62.7216 78.5934L62.7593 78.5683L62.7279 78.562L62.5397 78.5241L62.1445 78.3792L61.6803 78.2531L61.5485 78.2592L61.6676 78.3159L62.6212 78.6058L62.6275 78.5744ZM61.7184 77.9017C61.6347 77.8849 61.5845 77.8639 61.5678 77.8388L61.5868 77.7447C61.591 77.7238 61.6035 77.7154 61.6245 77.7196L61.5367 77.6693L61.4802 77.6253L61.2356 77.5434L61.223 77.6062L61.3358 77.6942C61.3692 77.7444 61.3859 77.7695 61.3859 77.7695L61.3232 77.7569L61.1099 77.6813C61.0932 77.6562 61.0974 77.6353 61.1225 77.6186L61.1665 77.5622L61.1792 77.4994C61.2043 77.4827 61.2085 77.4618 61.1918 77.4367L61.1731 77.3676L61.2421 77.3489L61.6624 77.5314C61.6581 77.5523 61.656 77.5628 61.656 77.5628C61.677 77.567 61.6874 77.5691 61.6874 77.5691L61.7 77.5064C61.7 77.5064 61.6896 77.5042 61.6687 77.5C61.6687 77.5 61.6708 77.4896 61.675 77.4687L61.7377 77.4813C61.9928 77.6197 62.16 77.7078 62.2394 77.7455L62.3209 77.8272L62.2268 77.8083L61.9571 77.6887L61.8881 77.7074L61.9131 77.7451L62.1138 77.8834C61.9255 77.8455 61.777 77.8265 61.6683 77.8264C61.6892 77.8306 61.6975 77.8431 61.6933 77.8641C61.7142 77.8683 61.7226 77.8808 61.7184 77.9017ZM64.5748 82.0348C64.5958 82.039 64.6083 82.0307 64.6125 82.0097C64.6377 81.993 64.6523 81.9742 64.6565 81.9533C64.665 81.9115 64.6817 81.8822 64.7068 81.8655L64.6755 81.8592L64.6188 81.9784C64.5979 81.9742 64.5854 81.9825 64.5812 82.0034L64.5748 82.0348ZM63.9112 80.7914L64.2815 80.7354C64.3234 80.7438 64.3694 80.7313 64.4196 80.6979C64.4783 80.6226 64.514 80.5537 64.5266 80.4909L64.5392 80.4282L64.4765 80.4155L64.1876 80.5532L64.0809 80.597C63.9009 80.6261 63.788 80.6469 63.7419 80.6594C63.6959 80.6719 63.6226 80.7115 63.5221 80.7783C63.5221 80.7783 63.52 80.7888 63.5158 80.8097C63.5158 80.8097 63.5263 80.8118 63.5472 80.816L63.9112 80.7914ZM62.9345 78.9953C62.9972 79.0079 63.0411 79.0059 63.0663 78.9892L63.0726 78.9578C63.0475 78.9745 63.0035 78.9765 62.9408 78.9639C62.9408 78.9639 62.9387 78.9744 62.9345 78.9953C62.9345 78.9953 62.924 78.9932 62.9031 78.989L62.9345 78.9953ZM63.2109 78.7571L63.2486 78.7321L63.2172 78.7258C63.1126 78.7047 63.0311 78.6774 62.9726 78.6439C62.9474 78.6606 62.9035 78.6626 62.8408 78.65L62.7717 78.6687L62.8281 78.7127L63.2109 78.7571ZM63.8748 79.8374C63.8748 79.8374 63.8643 79.8353 63.8434 79.8311L63.787 79.7871L63.7556 79.7808L63.8874 79.7747L63.9124 79.8124C63.9082 79.8333 63.8957 79.8416 63.8748 79.8374ZM63.2545 79.0271C63.3047 78.9936 63.3403 78.979 63.3612 78.9833L63.3362 78.9456L63.2294 78.9894L63.2545 79.0271ZM59.4575 74.215C59.5078 74.1816 59.5329 74.1649 59.5329 74.1649L59.7026 73.9706C59.7612 73.8953 59.8157 73.841 59.866 73.8076C59.8953 73.77 59.9372 73.724 59.9916 73.6697C60.0712 73.5987 60.1278 73.5339 60.1613 73.4754C60.1823 73.4796 60.1948 73.4712 60.199 73.4503L60.1927 73.4817C60.1885 73.5026 60.1864 73.5131 60.1864 73.5131C60.2073 73.5173 60.2199 73.5089 60.2241 73.488L60.4378 73.2373L60.4441 73.2059L60.4127 73.1996L60.1049 73.4314L59.6838 73.9015L59.4638 74.1837L59.4575 74.215ZM63.7189 78.99L63.7253 78.9586L63.6939 78.9523L63.5307 78.9521C63.5098 78.9479 63.4972 78.9562 63.493 78.9772L63.7189 78.99ZM63.1174 78.2487L63.2429 78.274L63.4625 78.3182L63.4875 78.3558L63.4499 78.3809L63.2616 78.343L63.2303 78.3367L63.1174 78.2487ZM64.9847 80.4852L64.9534 80.4789L64.7584 80.7987L64.7835 80.8364L64.9847 80.4852ZM64.3274 79.2104L64.3211 79.2418L64.3651 79.1854C64.3651 79.1854 64.3546 79.1833 64.3337 79.179C64.3337 79.179 64.3358 79.1686 64.34 79.1477C64.3024 79.1183 64.2501 79.1078 64.1832 79.1161C64.1581 79.1328 64.1246 79.1369 64.0828 79.1285C64.0451 79.0992 64.0263 79.0845 64.0263 79.0845C63.9845 79.0761 63.9657 79.0614 63.9699 79.0405C63.9783 78.9987 63.9574 78.9945 63.9072 79.0279C63.8862 79.0237 63.8528 79.0278 63.8067 79.0403C63.7816 79.057 63.7502 79.0507 63.7126 79.0214L63.6686 79.0778L63.6937 79.1155L63.7878 79.1344L64.3274 79.2104ZM60.5319 73.2562L60.5005 73.2499C60.4963 73.2708 60.4691 73.298 60.4188 73.3314L60.4439 73.3691L60.5319 73.2562ZM64.4843 79.242C64.5261 79.2504 64.5596 79.2463 64.5847 79.2296C64.6265 79.238 64.6495 79.2317 64.6537 79.2108C64.6579 79.1899 64.6496 79.1774 64.6287 79.1731L64.5659 79.1605C64.545 79.1563 64.5094 79.1709 64.4592 79.2043L64.4529 79.2357L64.4843 79.242ZM65.1984 80.2345L65.3557 79.9397C65.3557 79.9397 65.3054 79.9731 65.2049 80.0399L65.1986 80.0713C65.2153 80.0964 65.2111 80.1173 65.186 80.134C65.1818 80.1549 65.1776 80.1759 65.1734 80.1968C65.1482 80.2135 65.1357 80.2218 65.1357 80.2218C65.1566 80.226 65.1671 80.2281 65.1671 80.2281L65.1984 80.2345ZM65.2989 80.222C65.3198 80.2263 65.3323 80.2179 65.3365 80.197L65.3932 80.0778L65.3995 80.0464C65.3953 80.0674 65.3827 80.0757 65.3618 80.0715L65.3052 80.1907L65.2989 80.222ZM64.8733 79.255L64.867 79.2864L65.0302 79.2866L65.0616 79.2929C65.0658 79.272 65.0574 79.2595 65.0365 79.2552L64.8232 79.1797C64.7814 79.1712 64.7563 79.1879 64.7479 79.2298L64.7666 79.2988L64.8733 79.255ZM65.7564 80.7059C65.8066 80.6724 65.8423 80.6035 65.8633 80.4989C65.8633 80.4989 65.9136 80.4655 66.0141 80.3987C66.0434 80.3611 66.0686 80.29 66.0896 80.1854L66.0583 80.1791L65.8633 80.4989L65.7313 80.6682C65.7313 80.6682 65.7292 80.6786 65.725 80.6995C65.725 80.6995 65.7355 80.7016 65.7564 80.7059ZM65.4437 79.8269L65.6637 79.5447L65.67 79.5134L65.6387 79.507C65.6009 79.5865 65.5443 79.6513 65.469 79.7014L65.3999 79.7201L65.4123 79.8205L65.406 79.8519L65.4437 79.8269ZM66.473 79.7403L66.448 79.7026L66.3223 79.8405L66.3537 79.8468L66.473 79.7403ZM65.909 79.1371C65.9592 79.1037 65.9865 79.0765 65.9907 79.0556L65.997 79.0243C65.9467 79.0577 65.9216 79.0744 65.9216 79.0744C65.9216 79.0744 65.9174 79.0953 65.909 79.1371ZM66.1227 78.8864C66.1227 78.8864 66.1122 78.8843 66.0913 78.88C66.0913 78.88 66.0934 78.8696 66.0976 78.8487L66.0159 78.9302L66.0347 78.9992L66.1227 78.8864ZM66.5423 79.5584L66.6994 79.4268C66.6784 79.4226 66.668 79.4205 66.668 79.4205C66.6722 79.3996 66.6743 79.3891 66.6743 79.3891L66.6052 79.4079L66.5109 79.5521L66.536 79.5898L66.5423 79.5584ZM66.242 78.7798L66.217 78.7421C66.1667 78.7755 66.1395 78.8027 66.1353 78.8236C66.1144 78.8194 66.1018 78.8278 66.0976 78.8487C66.1185 78.8529 66.1394 78.8571 66.1604 78.8613L66.242 78.7798ZM66.286 78.7234C66.307 78.7276 66.3216 78.7088 66.33 78.667L66.3741 78.6105L66.6631 78.3097L66.7071 78.2533C66.6862 78.249 66.6757 78.2469 66.6757 78.2469C66.68 78.226 66.6821 78.2156 66.6821 78.2156L66.613 78.2343L66.6067 78.2657C66.5104 78.3116 66.4287 78.3931 66.3616 78.5101L66.2736 78.623L66.2296 78.6794L66.286 78.7234ZM62.1157 71.3881L62.097 71.319L62.053 71.3754L61.9776 71.4255L61.965 71.4883L61.9964 71.4946L62.1157 71.3881ZM66.9452 78.5297L66.9516 78.4983C66.8929 78.5736 66.8593 78.6321 66.8509 78.6739L66.9452 78.5297ZM62.5052 71.0748L62.5492 71.0183C62.5241 71.035 62.5011 71.0413 62.4802 71.0371C62.4844 71.0162 62.4739 71.0141 62.4488 71.0308L62.2604 71.156L62.2541 71.1874C62.2708 71.2125 62.254 71.2418 62.2037 71.2752C62.1995 71.2961 62.1723 71.3233 62.1221 71.3567C62.143 71.3609 62.1513 71.3735 62.1471 71.3944L62.5052 71.0748ZM67.5537 78.7501L67.56 78.7187L67.4973 78.7061L67.4406 78.8253L67.5537 78.7501ZM68.2176 79.8304C68.2427 79.8137 68.2552 79.8053 68.2552 79.8053C68.2804 79.7886 68.295 79.7698 68.2992 79.7489L68.3056 79.7175L68.2051 79.73C68.1967 79.7718 68.2009 79.8053 68.2176 79.8304ZM67.097 77.6136L67.0657 77.6073L66.984 77.6888L66.9777 77.7202L67.097 77.6136ZM62.7063 70.8867C62.6854 70.8825 62.677 70.87 62.6812 70.8491L62.6436 70.8741L62.5619 70.9556L62.5556 70.987L62.5869 70.9933L62.7063 70.8867ZM67.2164 77.5071C67.2666 77.4737 67.2939 77.4465 67.2981 77.4256L67.2667 77.4193L67.229 77.4443C67.229 77.4443 67.2248 77.4653 67.2164 77.5071ZM67.9567 77.7214C67.9651 77.6796 67.9609 77.6461 67.9442 77.621L67.9002 77.6774C67.85 77.7108 67.8228 77.738 67.8185 77.7589C67.7976 77.7547 67.7851 77.763 67.7809 77.7839L67.8122 77.7903L67.9567 77.7214ZM69.5311 78.3322C69.5437 78.2694 69.5626 78.2297 69.5877 78.213L69.6755 78.2633L69.7383 78.2759L69.6378 78.2884L69.5311 78.3322ZM69.5439 78.1062L69.5879 78.0498C69.5837 78.0707 69.5816 78.0812 69.5816 78.0812C69.6025 78.0854 69.613 78.0875 69.613 78.0875C69.6046 78.1293 69.6004 78.1502 69.6004 78.1502L69.5124 78.2631L69.5439 78.1062ZM63.8876 69.721C63.9085 69.7252 63.9211 69.7168 63.9253 69.6959L64.1011 69.6334L64.076 69.5957C64.0091 69.604 63.9588 69.6374 63.9253 69.6959C63.9044 69.6917 63.8918 69.7 63.8876 69.721ZM69.8195 78.5208C69.8406 78.4162 69.9034 78.3745 70.008 78.3955L70.0707 78.4081C70.0623 78.45 70.0476 78.4688 70.0267 78.4646L69.8446 78.5585L69.8195 78.5208ZM69.1372 77.2083C69.1456 77.1665 69.1602 77.1477 69.1812 77.1519C69.2063 77.1352 69.2502 77.1331 69.313 77.1458L69.3066 77.1771L69.1622 77.246L69.1372 77.2083ZM70.2406 78.0506L70.1842 78.0066L70.1214 77.994C70.1424 77.9982 70.1486 78.0212 70.1402 78.0631L70.065 77.95C70.0692 77.9291 70.0818 77.9207 70.1027 77.925C70.1278 77.9083 70.1404 77.8999 70.1404 77.8999L70.341 78.0382C70.3954 78.0927 70.4224 78.1743 70.4223 78.2831L70.2406 78.0506ZM69.6949 77.8429C69.6531 77.8344 69.6489 77.801 69.6825 77.7424L69.8395 77.6108L69.9465 77.4039C69.9967 77.3705 70.0218 77.3538 70.0218 77.3538C70.0595 77.3831 70.1034 77.3811 70.1536 77.3477C70.2123 77.2724 70.2772 77.2746 70.3482 77.3542L70.4737 77.3794L70.5741 77.367L70.5678 77.3984C70.5259 77.39 70.4925 77.3941 70.4673 77.4108C70.4255 77.4024 70.4004 77.4191 70.392 77.4609L70.4233 77.4672L70.2913 77.6365C70.1993 77.6615 70.124 77.6572 70.0654 77.6237L69.9964 77.6424L69.8583 77.6799L69.8143 77.7363C69.8477 77.7866 69.8623 77.8221 69.8581 77.8431L69.7263 77.8492L69.6949 77.8429ZM65.386 70.8713L65.832 70.602C65.878 70.5895 65.9513 70.5499 66.0518 70.4831L66.0267 70.4454C65.9513 70.4955 65.8425 70.5498 65.7002 70.6081L65.4804 70.7271C65.4343 70.7396 65.3611 70.7792 65.2606 70.8461L65.2166 70.9025L65.2479 70.9088L65.386 70.8713ZM70.5985 77.8942C70.5567 77.8858 70.5379 77.8711 70.5421 77.8502L70.5547 77.7875L70.6175 77.8001C70.6509 77.8503 70.6885 77.8797 70.7303 77.8881L70.5985 77.8942ZM70.5737 77.6934C70.557 77.6682 70.5172 77.6494 70.4545 77.6367L70.4231 77.6304L70.4671 77.574C70.4671 77.574 70.465 77.5844 70.4608 77.6053C70.4608 77.6053 70.4713 77.6075 70.4922 77.6117C70.534 77.6201 70.5633 77.6369 70.58 77.662L70.6114 77.6683L70.5737 77.6934ZM64.2582 69.5018C64.2624 69.4809 64.2645 69.4704 64.2645 69.4704C64.2854 69.4746 64.2958 69.4767 64.2958 69.4767C64.3628 69.4684 64.413 69.435 64.4466 69.3765L64.566 69.27C64.6203 69.3244 64.681 69.2931 64.7481 69.1761L64.7794 69.1824L65.1123 68.9883L65.3635 68.8756L65.3761 68.8129C65.4012 68.7962 65.4243 68.7899 65.4452 68.7941C65.487 68.8026 65.5205 68.7984 65.5456 68.7817L65.5519 68.7503C65.5101 68.7419 65.4766 68.7461 65.4515 68.7628C65.4515 68.7628 65.4264 68.7795 65.3761 68.8129C65.3761 68.8129 65.3657 68.8108 65.3447 68.8066C65.328 68.7814 65.3176 68.7793 65.3134 68.8002C65.2882 68.8169 65.2506 68.842 65.2003 68.8754C65.1543 68.8879 65.1249 68.9255 65.1123 68.9883C65.0998 68.9422 65.0433 68.9526 64.9428 69.0194C64.9219 69.0152 64.8863 69.0298 64.8361 69.0632C64.79 69.0757 64.7607 69.1133 64.7481 69.1761C64.6644 69.1592 64.6037 69.1905 64.566 69.27C64.5241 69.2616 64.5011 69.2678 64.4969 69.2887C64.4927 69.3096 64.478 69.3284 64.4529 69.3451C64.4278 69.3618 64.4027 69.3785 64.3775 69.3952L64.2708 69.439L64.2582 69.5018ZM65.69 68.7129C65.8826 68.6211 66.0291 68.5418 66.1296 68.4749L66.1736 68.4185C66.1318 68.4101 66.0983 68.4142 66.0732 68.4309L65.822 68.5436L65.5709 68.6562L65.5269 68.7127L65.5896 68.7253L65.69 68.7129ZM66.1736 68.4185C66.2155 68.4269 66.2489 68.4228 66.2741 68.4061L66.3431 68.3874L66.3181 68.3497L66.1799 68.3871L66.1736 68.4185ZM68.1051 69.5255L68.0487 69.4815L67.8666 69.5754L67.8853 69.6445L68.1051 69.5255ZM73.0145 85.2681C72.9099 85.247 72.8242 85.1862 72.7574 85.0857L72.6382 85.0291C72.4918 84.9996 72.3769 84.9221 72.2934 84.7965C72.2139 84.7587 72.1491 84.7021 72.099 84.6268C72.028 84.5472 71.9298 84.4948 71.8043 84.4695C71.7791 84.4862 71.7373 84.4778 71.6788 84.4442C71.6203 84.4107 71.5701 84.3897 71.5283 84.3813L71.1583 84.111C71.0498 83.8933 70.9099 83.7237 70.7385 83.6021C70.6256 83.5141 70.5379 83.4638 70.4751 83.4512C70.3705 83.4301 70.31 83.3526 70.2934 83.2187C70.2642 83.1476 70.1535 83.0491 69.9612 82.9233C69.8065 82.8269 69.6541 82.6113 69.5039 82.2764C69.4747 82.2052 69.4143 81.9646 69.3228 81.5544C69.3062 81.4205 69.3189 81.3034 69.3609 81.203L69.3295 81.1967L69.4931 80.8706C69.5686 80.7117 69.6127 80.6009 69.6253 80.5381L69.7386 80.2998C69.7888 80.2664 69.8328 80.21 69.8706 80.1305C69.9083 80.0511 69.9293 80.0009 69.9335 79.98C69.8834 79.9046 69.873 79.8481 69.9024 79.8105C69.9568 79.7562 69.9862 79.7186 69.9904 79.6977C70.0408 79.5555 70.1183 79.4405 70.223 79.3528C70.3194 79.1981 70.4222 79.0121 70.5312 78.7946C70.5732 78.6943 70.6675 78.5501 70.8142 78.362C70.8729 78.2867 71.051 78.0506 71.3485 77.6535C71.4534 77.457 71.5498 77.3023 71.6378 77.1895C71.73 77.0557 71.8076 76.9407 71.8704 76.8446C72.0087 76.6983 72.1428 76.5186 72.2728 76.3054C72.3984 76.2219 72.478 76.0965 72.5117 75.9292L72.5684 75.81L72.7067 75.6093C72.7276 75.6135 72.7506 75.6073 72.7757 75.5906C72.8009 75.5739 72.8155 75.5551 72.8197 75.5342L72.9014 75.4527C73.1361 75.1518 73.2723 74.9616 73.3101 74.8821C73.4232 74.7526 73.5238 74.6314 73.6118 74.5185C73.704 74.3847 73.7794 74.2802 73.8381 74.205L74.1901 73.7536C74.2237 73.6951 74.2886 73.5885 74.3851 73.4338C74.4815 73.2791 74.5842 73.1475 74.6931 73.0388C74.8355 72.8716 74.9299 72.7274 74.976 72.6062L75.2653 72.1421C75.3449 72.0711 75.4015 72.0063 75.435 71.9478C75.4728 71.8683 75.5063 71.8098 75.5356 71.7722C75.5483 71.7095 75.5986 71.6217 75.6866 71.5088C75.7326 71.4963 75.7494 71.467 75.7369 71.421C75.7495 71.3583 75.7475 71.3143 75.7308 71.2892L75.5678 71.1258C75.572 71.1049 75.5658 71.0819 75.5491 71.0568C75.5575 71.0149 75.5743 70.9857 75.5994 70.969C75.6205 70.8644 75.6143 70.787 75.5809 70.7368L75.5935 70.674L75.6188 70.5485C75.6064 70.3937 75.6651 70.3185 75.7948 70.3228C75.845 70.2894 75.9267 70.2623 76.0396 70.2416C76.3117 70.1875 76.5482 70.0937 76.7492 69.9601C76.791 69.9685 76.8182 69.9413 76.8308 69.8786L77.2271 69.2076C77.2564 69.17 77.2648 69.1281 77.2523 69.0821C77.2607 69.0403 77.2817 68.9901 77.3153 68.9316C77.3446 68.8939 77.3907 68.8271 77.4536 68.7309C77.5416 68.6181 77.6316 68.5491 77.7237 68.5241C77.8996 68.4072 78.1025 68.3719 78.3326 68.4182C78.5417 68.4603 78.6965 68.5024 78.7968 68.5443C78.8972 68.5863 78.9891 68.6701 79.0727 68.7957C79.1312 68.8293 79.1876 68.8733 79.2419 68.9277C79.2962 68.9822 79.3527 69.0262 79.4112 69.0597C79.4237 69.1058 79.4676 69.1581 79.5428 69.2168C79.6389 69.2797 79.7058 69.3258 79.7434 69.3551L79.9816 69.6315C80.015 69.6818 80.0631 69.7132 80.1258 69.7259C80.3476 69.7052 80.5296 69.6657 80.6719 69.6073C81.1532 69.4866 81.6052 69.4035 82.0278 69.358C82.3543 69.2496 82.6723 69.1831 82.982 69.1584C83.2749 69.1086 83.505 69.1005 83.6723 69.1342L83.8919 69.1784L84.1743 69.2352C84.1952 69.2394 84.2453 69.2604 84.3248 69.2982C84.4084 69.315 84.4649 69.359 84.4941 69.4302C84.5108 69.4553 84.54 69.4721 84.5819 69.4805C84.6237 69.4889 84.6634 69.5078 84.701 69.5371C84.7177 69.5623 84.747 69.579 84.7888 69.5875C84.8097 69.5917 84.8181 69.6042 84.8139 69.6251L84.7825 69.6188C84.7616 69.6146 84.7386 69.6209 84.7135 69.6376C84.7092 69.6585 84.7071 69.6689 84.7071 69.6689L84.7259 69.738L84.6882 69.763L84.7006 69.8635L84.9139 69.939C84.9139 69.939 84.9306 69.9642 84.964 70.0144C84.9807 70.0395 84.9953 70.0751 85.0078 70.1212C85.0245 70.1463 85.037 70.1923 85.0453 70.2593C85.0326 70.322 85.0451 70.3681 85.0828 70.3974C85.1204 70.4267 85.1475 70.454 85.1642 70.4791C85.1852 70.4833 85.206 70.5419 85.2268 70.6549C85.2644 70.6842 85.2915 70.7114 85.3083 70.7366C85.3459 70.7659 85.373 70.7931 85.3897 70.8183C85.4565 70.9188 85.4585 71.0171 85.3956 71.1132C85.3704 71.2387 85.341 71.3307 85.3074 71.3892L85.3009 71.5838C85.305 71.6716 85.2881 71.7553 85.2504 71.8347L85.0805 72.1922L84.9422 72.3929L84.8794 72.3803C84.846 72.33 84.8586 72.2673 84.9173 72.192C84.9424 72.1753 84.9592 72.1461 84.9676 72.1042C84.9803 72.0415 84.9782 71.9976 84.9615 71.9724C84.949 71.9264 84.9365 71.8804 84.924 71.8343C84.9115 71.7883 84.8635 71.7569 84.7798 71.74C84.7589 71.7358 84.7442 71.7546 84.7358 71.7964L84.6918 71.8529L84.7044 71.7901C84.6877 71.765 84.6857 71.7211 84.6983 71.6583L84.5101 71.6204L84.416 71.6015C84.3575 71.5679 84.2738 71.5511 84.165 71.551C83.847 71.6175 83.6105 71.6569 83.4557 71.6693C83.1837 71.7233 82.7778 71.7939 82.238 71.8811C81.7944 71.9224 81.4701 71.9659 81.2651 72.0117C81.1521 72.0325 80.9826 72.0636 80.7566 72.1052C80.5348 72.1258 80.3487 72.1318 80.1981 72.1233C80.1311 72.1316 80.0516 72.1482 79.9595 72.1732C79.8926 72.1815 79.813 72.1981 79.721 72.2231C79.5871 72.2397 79.5201 72.2479 79.5201 72.2479C79.3862 72.2645 79.2774 72.2644 79.1938 72.2475C79.1687 72.2642 79.1226 72.2767 79.0557 72.285C78.9929 72.2724 78.9594 72.2765 78.9552 72.2974L78.8609 72.4416L78.4836 73.0185C78.425 73.0938 78.3391 73.1962 78.2259 73.3257C78.1379 73.4386 78.0604 73.5535 77.9933 73.6706C77.8466 73.8587 77.7398 74.0112 77.6727 74.1283C77.5847 74.2412 77.4862 74.3519 77.3773 74.4605C77.2893 74.5734 77.1992 74.6967 77.107 74.8305L76.9813 74.9684L76.975 74.9997L77.0377 75.0124L77.4457 74.9313C77.5754 74.9357 77.6904 74.9588 77.7908 75.0008C77.8284 75.0301 77.9518 75.0658 78.1609 75.1079C78.2237 75.1206 78.2592 75.1604 78.2675 75.2273C78.2842 75.2524 78.3134 75.2692 78.3553 75.2776C78.5308 75.3783 78.6396 75.4328 78.6814 75.4412L78.6688 75.504L78.6374 75.4976C78.6165 75.4934 78.6039 75.5018 78.5997 75.5227C78.5955 75.5436 78.5829 75.552 78.562 75.5477C78.5829 75.552 78.5913 75.5645 78.5871 75.5854C78.5829 75.6063 78.5912 75.6189 78.6121 75.6231L78.8254 75.6987L78.8568 75.705L78.9633 75.8244L78.8252 75.8619C78.7415 75.845 78.6871 75.845 78.662 75.8617L78.6307 75.8553C78.6264 75.8763 78.6348 75.8888 78.6557 75.893L78.7435 75.9433L79.0572 76.0065C79.099 76.0149 79.1576 76.0485 79.2328 76.1071C79.2536 76.2201 79.2932 76.2934 79.3518 76.3269L79.5337 76.3962C79.5922 76.4297 79.6173 76.4674 79.6088 76.5093C79.6046 76.5302 79.5921 76.5385 79.5711 76.5343L79.3328 76.4211L79.2701 76.4084C79.291 76.4126 79.2993 76.4252 79.2951 76.4461C79.3034 76.5131 79.3347 76.5738 79.389 76.6282C79.4685 76.666 79.527 76.6995 79.5646 76.7289L79.7964 77.0367C79.7964 77.0367 79.7943 77.0471 79.7901 77.068C79.7901 77.068 79.8006 77.0701 79.8215 77.0743L79.7274 77.0554C79.7316 77.0345 79.7232 77.0219 79.7023 77.0177C79.6814 77.0135 79.671 77.0114 79.671 77.0114C79.6669 76.9235 79.6502 76.8984 79.6208 76.936C79.5957 76.9527 79.5727 76.959 79.5518 76.9548L79.5579 77.0866L79.6895 77.2436C79.6895 77.2436 79.6874 77.2541 79.6832 77.275C79.6999 77.3001 79.7187 77.3148 79.7396 77.319C79.6978 77.3106 79.6602 77.2812 79.6267 77.231L79.5954 77.2247C79.5954 77.2247 79.5745 77.2205 79.5326 77.212L79.5451 77.3125C79.7039 77.388 79.8084 77.4634 79.8586 77.5388L79.9712 77.79L80.0213 77.8653C80.0589 77.8947 80.0526 77.926 80.0024 77.9595C79.9772 77.9762 79.9438 77.9803 79.9019 77.9719L79.7327 77.8399L79.4693 77.6889C79.394 77.6303 79.3668 77.6574 79.3876 77.7704L79.3813 77.8018L79.3562 77.7641C79.3437 77.718 79.2935 77.6971 79.2057 77.7011L78.2203 77.7313L77.2978 77.774L77.0279 77.8176C76.6973 77.8381 76.3793 77.8503 76.0739 77.854C75.9651 77.8539 75.8542 77.8642 75.7412 77.885C75.6325 77.8849 75.5028 77.8805 75.3522 77.872C75.3103 77.8635 75.2329 77.8697 75.1199 77.8905C75.0112 77.8904 74.9045 77.8798 74.7999 77.8587L74.6932 77.9025C74.5297 78.1742 74.4081 78.3456 74.3285 78.4166L74.1715 78.5482C73.9955 78.7739 73.8006 79.0394 73.5868 79.3445C73.4988 79.4574 73.4066 79.5911 73.3102 79.7458C73.2389 79.8838 73.1341 80.0259 72.9958 80.1722C72.6688 80.7156 72.4675 81.0668 72.392 81.2257C72.3543 81.3052 72.3144 81.3951 72.2725 81.4954C72.2347 81.5749 72.2032 81.6773 72.1779 81.8028C72.1402 81.8822 72.1652 81.9199 72.2531 81.9159C72.3243 81.8867 72.3807 81.8763 72.4226 81.8847C72.4895 81.8764 72.5335 81.8744 72.5544 81.8786L72.5857 81.8849C72.5648 81.8807 72.5523 81.889 72.5481 81.91L72.2028 82.0037C72.1819 81.9994 72.1588 82.0057 72.1337 82.0224C72.1337 82.0224 72.1233 82.0203 72.1023 82.0161L72.2278 82.0413L72.4851 82.0605L72.5479 82.0731L72.5102 82.0982L72.2089 82.1355C72.1419 82.1437 72.0938 82.1667 72.0645 82.2043C72.0393 82.221 72.0309 82.2628 72.0392 82.3298C72.035 82.3507 72.0308 82.3716 72.0266 82.3925C72.0475 82.3967 72.0558 82.4093 72.0516 82.4302C72.0432 82.472 72.0808 82.5014 72.1645 82.5182L72.4217 82.5374C72.4887 82.5291 72.5661 82.5229 72.654 82.5188C72.767 82.4981 72.8757 82.4982 72.9803 82.5193L73.0431 82.5319C73.064 82.5361 73.0849 82.5403 73.1058 82.5445C73.1476 82.5529 73.1769 82.5697 73.1936 82.5948C73.2604 82.6953 73.3294 82.731 73.4006 82.7018L74.4362 82.5839L74.8756 82.5091L74.9383 82.5217C74.9802 82.5302 75.0471 82.5219 75.1392 82.4969C75.2313 82.4719 75.3212 82.4574 75.4091 82.4533C75.4551 82.4408 75.5242 82.4221 75.6163 82.3971C75.7335 82.3554 75.8465 82.3346 75.9552 82.3348C75.9762 82.339 76.1226 82.3141 76.3946 82.26C76.5285 82.2434 76.6311 82.2206 76.7022 82.1914C76.7943 82.1664 76.8738 82.1498 76.9408 82.1415C77.1123 82.1542 77.2002 82.1502 77.2044 82.1293L77.2484 82.0728C77.2693 82.077 77.2776 82.0896 77.2734 82.1105C77.2692 82.1314 77.2671 82.1419 77.2671 82.1419C77.3425 82.0918 77.3717 82.1085 77.3549 82.1922C77.3716 82.2173 77.3904 82.232 77.4113 82.2362C77.4532 82.2446 77.4762 82.2384 77.4804 82.2175L77.5118 82.2238L77.5745 82.2364L77.5808 82.205L77.5934 82.1423C77.5977 82.1214 77.6102 82.113 77.6311 82.1172L77.6248 82.1486L77.6059 82.2427C77.6059 82.2427 77.5807 82.2594 77.5305 82.2928L77.5179 82.3556C77.5137 82.3765 77.5094 82.3974 77.5052 82.4183C77.5261 82.4225 77.5345 82.4351 77.5303 82.456C77.547 82.4811 77.6013 82.5356 77.6932 82.6194C77.7142 82.6236 77.7225 82.6362 77.7183 82.6571C77.7683 82.8412 77.8246 82.9396 77.8874 82.9522C77.9083 82.9565 77.9208 82.9481 77.9251 82.9272C77.9502 82.9105 77.9732 82.9042 77.9941 82.9084L78.0318 82.8834C78.0318 82.8834 78.0297 82.8938 78.0255 82.9148C78.0464 82.919 78.0673 82.9232 78.0882 82.9274L78.0819 82.9588L78.0567 83.0842C78.0776 83.0885 78.1131 83.0739 78.1634 83.0405C78.2136 83.007 78.2409 82.9799 78.2451 82.959C78.2451 82.959 78.2472 82.9485 78.2514 82.9276C78.2765 82.9109 78.2912 82.8921 78.2954 82.8712C78.3163 82.8754 78.3247 82.8879 78.3205 82.9089C78.3162 82.9298 78.3246 82.9423 78.3455 82.9465L78.3392 82.9779C78.2889 83.0113 78.268 83.0615 78.2762 83.1285C78.2929 83.1536 78.295 83.1975 78.2824 83.2603C78.3031 83.3732 78.3596 83.4172 78.4516 83.3923C78.5186 83.384 78.5709 83.3945 78.6085 83.4238C78.6544 83.5201 78.6333 83.6247 78.5453 83.7375C78.449 83.7834 78.4029 83.8503 78.407 83.9382C78.4111 84.0261 78.411 84.0804 78.4068 84.1014L78.3436 84.4151L78.306 84.4401C78.306 84.4401 78.2955 84.438 78.2746 84.4338C78.2537 84.4296 78.2453 84.417 78.2495 84.3961C78.191 84.3626 78.1576 84.3123 78.1493 84.2454C78.1368 84.1993 78.118 84.1847 78.0929 84.2014C77.984 84.31 77.8207 84.3642 77.6032 84.3639C77.4902 84.3847 77.3563 84.4013 77.2015 84.4136C77.0676 84.4302 76.9211 84.4551 76.7621 84.4884C76.6282 84.5049 76.4796 84.5403 76.3164 84.5945L76.285 84.5882C76.2474 84.5588 76.2034 84.5609 76.1532 84.5943C76.1029 84.6277 76.0674 84.6423 76.0464 84.6381L76.0088 84.6631L75.8833 84.6379C75.8497 84.6964 75.7995 84.7298 75.7325 84.7381C75.6656 84.7464 75.6216 84.7484 75.6007 84.7442L75.4062 84.7377C75.2723 84.7542 75.1613 84.8189 75.0733 84.9318L75.042 84.9255C74.9792 84.9128 74.8914 84.9169 74.7784 84.9377C74.6654 84.9585 74.5754 84.973 74.5085 84.9813L74.2322 85.0562C74.2113 85.052 74.1757 85.0666 74.1255 85.1C74.0627 85.0874 74.0314 85.0811 74.0314 85.0811L73.9686 85.0685C73.9059 85.0558 73.8285 85.062 73.7364 85.087C73.6401 85.1329 73.5585 85.16 73.4916 85.1683L73.3471 85.2371L73.1086 85.287L73.0145 85.2681ZM72.5784 82.7321L72.6538 82.682L72.591 82.6694C72.5283 82.6567 72.4822 82.6692 72.4529 82.7069L72.4152 82.7319L72.478 82.7445L72.5784 82.7321ZM71.2389 79.9816L71.2955 79.8625C71.2997 79.8416 71.2914 79.829 71.2705 79.8248L71.2641 79.8562C71.239 79.8729 71.2201 79.9126 71.2075 79.9753L71.2389 79.9816ZM72.886 82.6635C72.9906 82.6845 73.0659 82.6888 73.1119 82.6763L73.1433 82.6826L73.1182 82.6449L72.886 82.6635L72.8546 82.6572C72.8546 82.6572 72.8525 82.6676 72.8483 82.6885C72.8692 82.6927 72.8818 82.6844 72.886 82.6635ZM71.4905 79.5427C71.5407 79.5093 71.5722 79.4612 71.5848 79.3984L71.5911 79.3671L71.5597 79.3608L71.4717 79.4736L71.4591 79.5364L71.4905 79.5427ZM75.1878 83.7144C75.2172 83.6768 75.2423 83.6601 75.2632 83.6643C75.2841 83.6685 75.3071 83.6623 75.3323 83.6456L75.7089 83.5582C75.7717 83.5708 75.8491 83.5647 75.9412 83.5397L75.9852 83.4833L75.9161 83.502C75.6985 83.5017 75.5312 83.5224 75.414 83.5641C75.3637 83.5975 75.2926 83.6267 75.2005 83.6517C75.1796 83.6475 75.1649 83.6663 75.1565 83.7081L75.1878 83.7144ZM75.3078 83.1184C75.446 83.0809 75.582 83.0539 75.7159 83.0373C75.8498 83.0208 75.9628 83 76.0548 82.975L76.1239 82.9563C76.0821 82.9479 76.0611 82.9436 76.0611 82.9436L75.6281 82.987C75.582 82.9995 75.5234 83.0204 75.4523 83.0496C75.4062 83.0621 75.3476 83.0829 75.2765 83.1121L75.2451 83.1058L75.2765 83.1121L75.3078 83.1184ZM76.4755 82.8312C76.6303 82.8189 76.7559 82.7897 76.8521 82.7438L76.9776 82.7691L76.8271 82.7061C76.6848 82.7645 76.5697 82.7958 76.4818 82.7998C76.4818 82.7998 76.4797 82.8103 76.4755 82.8312C76.4755 82.8312 76.465 82.8291 76.4441 82.8249L76.4755 82.8312ZM84.6036 72.1289L84.6162 72.0661C84.6289 72.0034 84.6477 71.9637 84.6729 71.947L84.7042 71.9533L84.6287 72.1666L84.5973 72.1603L84.6036 72.1289ZM94.1774 83.8816C94.1355 83.8731 94.1063 83.8564 94.0896 83.8312C94.098 83.7894 94.1064 83.7476 94.1148 83.7058L94.0649 83.4672C94.0692 83.4463 94.0608 83.4337 94.0399 83.4295C94.0692 83.3919 94.0651 83.3584 94.0275 83.3291C94.0108 83.304 94.0024 83.2914 94.0024 83.2914L93.7015 83.0023L93.7079 82.971C93.6871 82.858 93.6328 82.8035 93.5449 82.8076C93.5575 82.7449 93.5555 82.7009 93.5388 82.6758L93.6015 82.6884C93.5973 82.7093 93.5931 82.7303 93.5889 82.7512C93.6098 82.7554 93.6328 82.7491 93.658 82.7324C93.6622 82.7115 93.6852 82.7053 93.727 82.7137L93.7647 82.6886C93.7689 82.6677 93.7606 82.6552 93.7396 82.651C93.6853 82.5965 93.6728 82.5505 93.7022 82.5128C93.7357 82.4543 93.763 82.3728 93.7841 82.2682L93.7904 82.2368C93.8364 82.2243 93.8532 82.1951 93.8407 82.149C93.8533 82.0863 93.8617 82.0445 93.866 82.0235C93.8911 82.0068 93.91 81.9671 93.9226 81.9044L93.9352 81.8416L93.8598 81.8917C93.843 81.9754 93.8199 82.036 93.7906 82.0737L93.7529 82.0987L93.7592 82.0673L93.835 81.6909C93.8434 81.6491 93.8539 81.5968 93.8666 81.534C93.9043 81.4546 93.9086 81.3793 93.8794 81.3081C93.846 81.2579 93.8502 81.237 93.892 81.2454C94.001 81.1367 94.0555 81.028 94.0556 80.9193L94.0996 80.8628C94.1457 80.8503 94.1792 80.7918 94.2003 80.6872C94.2129 80.6245 94.236 80.5639 94.2695 80.5053C94.324 80.451 94.3533 80.4134 94.3575 80.3925L94.3702 80.3297L94.3011 80.3485L94.2885 80.4112L94.2571 80.4049L94.2634 80.3735L94.2887 80.2481C94.3139 80.1226 94.3433 80.0306 94.3769 79.972C94.3853 79.9302 94.4189 79.8717 94.4775 79.7964L94.4902 79.7337C94.4399 79.7671 94.4148 79.7838 94.4148 79.7838C94.3645 79.8172 94.2263 79.9635 94 80.2226C93.9414 80.2978 93.8869 80.3521 93.8367 80.3855L93.8303 80.4169C93.8177 80.4797 93.7653 80.5779 93.6731 80.7117C93.5851 80.8245 93.5326 80.9228 93.5158 81.0064C93.5158 81.0064 93.5137 81.0169 93.5095 81.0378C93.5095 81.0378 93.499 81.0357 93.4781 81.0315L93.4908 80.9687L93.6733 80.5485C93.7026 80.5109 93.7089 80.4795 93.6922 80.4544C93.7006 80.4126 93.7195 80.3728 93.7489 80.3352C93.7824 80.2767 93.8181 80.2077 93.8558 80.1283C93.9187 80.0321 93.9564 79.9527 93.9691 79.8899C93.9733 79.869 93.9796 79.8376 93.988 79.7958C94.0216 79.7373 94.0091 79.6912 93.9505 79.6577L94.0009 79.5699L94.0072 79.5385L93.9381 79.5573L93.9004 79.5823L93.9131 79.5196L94.196 79.0869L94.4979 78.5601L94.5106 78.4974C94.5106 78.4974 94.5001 78.4953 94.4792 78.4911C94.4792 78.4911 94.4771 78.5015 94.4729 78.5225C94.452 78.5183 94.4394 78.5266 94.4352 78.5475L94.3598 78.5976L94.3724 78.5349C94.3976 78.5182 94.4122 78.4994 94.4164 78.4785C94.4249 78.4366 94.4416 78.4074 94.4668 78.3907L94.4794 78.3279L94.4417 78.353L94.0394 78.8922L93.9954 78.9486L93.9577 78.9737L93.9703 78.9109C93.9787 78.8691 93.9934 78.8503 94.0143 78.8545C94.0772 78.7583 94.1317 78.6496 94.1779 78.5284C94.245 78.4113 94.3225 78.2963 94.4105 78.1835L94.9135 77.4687L95.4794 76.6034L95.7561 76.2021L96.0517 75.7067L96.3849 75.1862C96.4729 75.0734 96.584 74.8999 96.7182 74.6657C96.932 74.3606 97.0577 74.1683 97.0955 74.0889C97.2255 73.8757 97.3072 73.7398 97.3408 73.6813C97.4205 73.5014 97.605 73.1795 97.8942 72.7155C97.9529 72.6403 98.02 72.5232 98.0955 72.3643C98.2506 72.1344 98.3806 71.9212 98.4854 71.7247C98.5483 71.6285 98.6028 71.5198 98.649 71.3986C98.7161 71.2815 98.7936 71.1665 98.8816 71.0537C98.999 70.9032 99.1332 70.6691 99.2842 70.3513L99.6364 69.7367C99.6742 69.6573 99.7245 69.5695 99.7874 69.4734C99.8502 69.3772 99.9069 69.258 99.9573 69.1159C99.9824 69.0991 99.9887 69.0678 99.9762 69.0217C99.9679 68.9548 99.968 68.9004 99.9764 68.8586C99.9555 68.8544 99.9471 68.8418 99.9514 68.8209C99.9556 68.8 99.9577 68.7895 99.9577 68.7895C100.029 68.7603 100.071 68.7143 100.083 68.6516C100.1 68.568 100.111 68.5157 100.115 68.4948C100.128 68.432 100.167 68.3965 100.234 68.3882C100.234 68.3882 100.297 68.3465 100.423 68.2629C100.641 68.0457 100.821 67.9078 100.963 67.8494C101.239 67.7745 101.444 67.7287 101.578 67.7121L101.942 67.6875L102.576 67.9456C102.592 67.9707 102.632 67.9896 102.695 68.0023C102.841 68.0317 102.927 68.0925 102.952 68.1846L103.002 68.2599C103.019 68.2851 103.046 68.3123 103.084 68.3416C103.121 68.371 103.155 68.4212 103.184 68.4924C103.18 68.5133 103.186 68.5363 103.203 68.5614C103.244 68.5699 103.271 68.5971 103.284 68.6431C103.351 68.7436 103.376 68.8357 103.359 68.9194C103.359 69.1369 103.35 69.2875 103.333 69.3712L103.107 69.8478C102.905 70.199 102.744 70.4603 102.623 70.6317L102.421 70.9829L101.987 71.6789C101.874 71.8085 101.761 71.9924 101.648 72.2308C101.463 72.4983 101.335 72.701 101.264 72.839L101.088 73.0647C101.076 73.1275 101.055 73.1776 101.025 73.2153L100.749 73.6165L100.453 74.112L99.8744 75.04L99.6167 75.3472L99.3715 75.7548C99.2792 75.8886 99.1745 76.0307 99.0571 76.1812C98.9398 76.3316 98.8057 76.5114 98.6548 76.7204L98.0891 77.4225L97.2404 78.5574L96.4987 79.4852L96.1277 80.0307C96.0649 80.1269 96.002 80.223 95.9391 80.3192C95.9014 80.3986 95.8657 80.4676 95.8322 80.5261L95.4235 81.0967L94.8639 81.9307L94.562 82.4575C94.5243 82.5369 94.5367 82.5829 94.5995 82.5956L94.6182 82.6646C94.614 82.6855 94.5847 82.7232 94.5302 82.7775C94.5009 82.8151 94.5134 82.8611 94.5677 82.9156C94.4419 83.1079 94.379 83.2584 94.3789 83.3672C94.3746 83.3881 94.3474 83.4153 94.2972 83.4487L94.2782 83.5428L94.3723 83.5617L94.3911 83.6308C94.37 83.7354 94.3427 83.8169 94.3092 83.8754C94.2589 83.9089 94.215 83.9109 94.1774 83.8816ZM89.5681 86.1852L89.6308 86.1978L89.5807 86.1224L89.4676 86.1976L89.4927 86.2353L89.5681 86.1852ZM89.8942 86.3487C89.8984 86.3278 89.8901 86.3153 89.8691 86.3111L89.8818 86.2483L89.8881 86.2169L89.8253 86.2043C89.8169 86.2461 89.8002 86.2754 89.775 86.2921C89.8084 86.3424 89.8251 86.3675 89.8251 86.3675L89.8942 86.3487ZM90.8593 87.3917C90.8384 87.3875 90.8175 87.3833 90.7966 87.3791C90.8008 87.3582 90.8029 87.3477 90.8029 87.3477L90.7025 87.3602L90.7212 87.4292L90.8593 87.3917ZM90.7029 87.0338C90.7071 87.0129 90.7301 87.0067 90.772 87.0151L90.7155 86.9711C90.6528 86.9585 90.6089 86.9605 90.5837 86.9772C90.5628 86.973 90.5481 86.9918 90.5397 87.0336L90.5898 87.109L90.7029 87.0338ZM90.07 86.2862C90.0909 86.2904 90.1265 86.2758 90.1767 86.2424L90.1517 86.2047C90.1014 86.2381 90.0763 86.2548 90.0763 86.2548L90.07 86.2862ZM89.9386 85.966L89.9702 85.8091C89.9786 85.7673 89.9724 85.7443 89.9515 85.7401L89.9075 85.7965C89.9032 85.8174 89.8969 85.8488 89.8885 85.8906C89.8843 85.9115 89.8592 85.9282 89.8131 85.9407L89.8382 85.9784C89.8549 86.0035 89.8842 86.0203 89.926 86.0287L89.9386 85.966ZM90.465 86.5942L90.4713 86.5629L90.3584 86.4748L90.2957 86.4622L90.3208 86.4999C90.3542 86.5502 90.3918 86.5795 90.4336 86.5879L90.465 86.5942ZM90.6225 86.1363L90.6288 86.1049C90.633 86.084 90.6246 86.0714 90.6037 86.0672C90.5577 86.0797 90.5263 86.0734 90.5096 86.0483C90.472 86.019 90.4302 86.0105 90.3841 86.023C90.359 86.0397 90.3443 86.0585 90.3401 86.0795C90.3401 86.0795 90.3652 86.1171 90.4153 86.1925L90.4467 86.1988L90.478 86.2051L90.6225 86.1363ZM90.2026 85.6274C90.211 85.5856 90.2278 85.5563 90.2529 85.5396L90.2342 85.4706L90.2028 85.4643L90.1588 85.5207L90.1649 85.6525L90.19 85.6902L90.2026 85.6274ZM90.6517 87.7743C90.6308 87.7701 90.5995 87.7638 90.5576 87.7553C90.5367 87.7511 90.5409 87.7302 90.5703 87.6926C90.5954 87.6759 90.5975 87.6654 90.5766 87.6612C90.5808 87.6403 90.5724 87.6278 90.5515 87.6236C90.5348 87.5984 90.5056 87.5817 90.4637 87.5732C90.4428 87.569 90.424 87.5544 90.4073 87.5292C90.3906 87.5041 90.3948 87.4832 90.4199 87.4665L90.4452 87.341C90.4997 87.2867 90.4851 87.2511 90.4014 87.2343C90.2759 87.209 90.2446 87.1483 90.3075 87.0522L90.2951 86.9517L90.2637 86.9454L90.2197 87.0018C90.2322 87.0479 90.2154 87.0771 90.1694 87.0896C90.1443 87.1063 90.1296 87.1251 90.1254 87.1461L90.1003 87.1084C90.1045 87.0875 90.0983 87.0644 90.0816 87.0393C90.0858 87.0184 90.0649 87.0142 90.0189 87.0267L90.0252 86.9953C90.0128 86.8405 89.9397 86.7714 89.8058 86.7879C89.7849 86.7837 89.7535 86.7774 89.7117 86.769C89.6908 86.7648 89.6615 86.748 89.6239 86.7187C89.6072 86.6935 89.557 86.6726 89.4733 86.6557C89.3897 86.6389 89.3563 86.5886 89.3731 86.505L89.4552 86.0972L89.4678 86.0344L89.4491 85.9654L89.4051 86.0218C89.4134 86.0887 89.3757 86.1138 89.292 86.097C89.292 86.097 89.2816 86.0948 89.2607 86.0906C89.2607 86.0906 89.2628 86.0802 89.267 86.0593L89.4685 85.5449L89.5567 85.2689C89.5651 85.2271 89.5568 85.1601 89.5318 85.068C89.5193 85.022 89.5424 84.9614 89.6011 84.8861L89.8209 84.7672L90.1725 84.6421C90.1976 84.6254 90.2165 84.5857 90.2291 84.5229C90.246 84.4393 90.3025 84.3745 90.3988 84.3286C90.5327 84.312 90.6582 84.3373 90.7753 84.4044C90.8338 84.4379 90.8295 84.5132 90.7624 84.6303L90.6113 85.0569L90.63 85.1259L90.6991 85.1072C90.7159 85.0235 90.7537 84.9441 90.8123 84.8688C90.8668 84.8145 90.9296 84.7728 91.0008 84.7436C91.0259 84.7269 91.0321 84.7499 91.0195 84.8126L91.0132 84.844L91.0822 84.8253L91.1262 84.7688L91.1576 84.7751L91.2768 84.8318C91.3186 84.8402 91.3521 84.8361 91.3772 84.8194L91.3208 84.7754C91.2874 84.7251 91.302 84.7063 91.3648 84.7189C91.528 84.6647 91.7309 84.6838 91.9735 84.7762C92.0571 84.793 92.0884 84.8537 92.0674 84.9583L92.0484 85.0524C92.0233 85.0691 92.0191 85.09 92.0358 85.1151C92.0567 85.1194 92.0776 85.1236 92.0985 85.1278C92.1446 85.1153 92.1738 85.1321 92.1863 85.1781C92.2239 85.2074 92.2532 85.2242 92.2741 85.2284L92.4308 85.4232L92.5685 85.712L92.5622 85.7434C92.6205 85.8857 92.5765 85.9421 92.4301 85.9127C92.3883 85.9042 92.3632 85.9209 92.3548 85.9628L92.2918 86.1133C92.2416 86.1467 92.231 86.199 92.2602 86.2702C92.2852 86.3622 92.3144 86.4334 92.3478 86.4837L92.3415 86.515L92.2788 86.5024L92.2537 86.4647C92.1952 86.4312 92.1513 86.4332 92.1219 86.4708L92.1156 86.5022C92.1114 86.5231 92.0946 86.5524 92.0653 86.59C92.036 86.6276 91.9983 86.6527 91.9522 86.6651C91.9271 86.6818 91.8957 86.7299 91.8579 86.8094C91.8453 86.8721 91.8452 86.9265 91.8577 86.9725L91.8514 87.0039C91.8472 87.0248 91.82 87.052 91.7697 87.0854C91.7195 87.1188 91.7089 87.1711 91.7381 87.2422L91.7318 87.2736C91.6649 87.2819 91.6585 87.3133 91.7129 87.3677C91.7129 87.3677 91.7108 87.3782 91.7065 87.3991C91.7275 87.4033 91.7275 87.4033 91.7065 87.3991C91.6897 87.4827 91.6457 87.5392 91.5745 87.5684C91.5703 87.5893 91.5305 87.6248 91.4552 87.6749C91.4091 87.6874 91.3631 87.6999 91.3171 87.7124C91.271 87.7249 91.2229 87.7478 91.1726 87.7812C91.0512 87.8438 90.9215 87.8395 90.7835 87.7682L90.6517 87.7743ZM90.8496 85.1701C90.8789 85.1325 90.9062 85.1053 90.9313 85.0886C90.9606 85.051 90.9795 85.0113 90.9879 84.9695L90.9692 84.9004L90.9566 84.9632L90.9439 85.0259L90.8559 85.1388L90.8496 85.1701ZM92.519 85.1471C92.4981 85.1429 92.4793 85.1283 92.4626 85.1031C92.4458 85.078 92.4417 85.0445 92.4501 85.0027C92.4753 84.986 92.4857 84.9881 92.4815 85.009C92.5233 85.0174 92.5819 85.051 92.6571 85.1097L92.519 85.1471ZM93.0745 82.5497C93.0411 82.4995 93.0286 82.4534 93.0371 82.4116C93.0162 82.4074 93.0099 82.3844 93.0183 82.3425L93.0811 82.3552L93.1876 82.4745C93.2043 82.4997 93.244 82.5185 93.3068 82.5312C93.3068 82.5312 93.3172 82.5333 93.3381 82.5375C93.3339 82.5584 93.3214 82.5667 93.3005 82.5625L93.131 82.5937L93.0745 82.5497ZM94.5085 80.1291L94.6468 79.9284L94.6531 79.8971L94.6218 79.8908L94.4834 80.0914C94.4625 80.0872 94.45 80.0955 94.4457 80.1165C94.4667 80.1207 94.4771 80.1228 94.4771 80.1228L94.5085 80.1291ZM94.1516 79.4697C94.1934 79.4781 94.2165 79.4719 94.2207 79.4509C94.25 79.4133 94.2668 79.3841 94.271 79.3632L94.2773 79.3318L94.2019 79.3819L94.1579 79.4383C94.137 79.4341 94.1244 79.4425 94.1202 79.4634L94.1516 79.4697ZM94.428 79.2316C94.3946 79.1813 94.3779 79.1562 94.3779 79.1562C94.3737 79.1771 94.3465 79.2043 94.2962 79.2377L94.2899 79.269L94.428 79.2316ZM96.3058 78.1734L96.2871 78.1043L96.2054 78.1858L96.1928 78.2485L96.3058 78.1734ZM97.8337 75.9349C97.8546 75.9391 97.8671 75.9307 97.8714 75.9098C97.8798 75.868 97.9049 75.8513 97.9467 75.8597C97.9676 75.8639 97.9823 75.8451 97.9907 75.8033L97.9657 75.7656C97.9448 75.7614 97.9217 75.7676 97.8966 75.7843C97.8715 75.801 97.8757 75.7801 97.9093 75.7216L97.8779 75.7153C97.861 75.7989 97.838 75.8596 97.8086 75.8972L97.8337 75.9349ZM100.611 85.1767C100.569 85.1683 100.54 85.1516 100.523 85.1264C100.531 85.0846 100.54 85.0428 100.548 85.0009L100.498 84.7624C100.503 84.7415 100.494 84.7289 100.473 84.7247C100.503 84.6871 100.498 84.6536 100.461 84.6243C100.444 84.5992 100.436 84.5866 100.436 84.5866L100.135 84.2975L100.141 84.2662C100.121 84.1532 100.066 84.0987 99.9783 84.1028C99.9909 84.0401 99.9889 83.9961 99.9722 83.971L100.035 83.9836C100.031 84.0045 100.027 84.0255 100.022 84.0464C100.043 84.0506 100.066 84.0443 100.091 84.0276C100.096 84.0067 100.119 84.0005 100.16 84.0089L100.198 83.9838C100.202 83.9629 100.194 83.9504 100.173 83.9461C100.119 83.8917 100.106 83.8457 100.136 83.808C100.169 83.7495 100.196 83.668 100.217 83.5634L100.224 83.532C100.27 83.5195 100.287 83.4903 100.274 83.4442C100.287 83.3815 100.295 83.3396 100.299 83.3187C100.324 83.302 100.343 83.2623 100.356 83.1996L100.369 83.1368L100.293 83.1869C100.276 83.2706 100.253 83.3312 100.224 83.3688L100.186 83.3939L100.193 83.3625L100.268 82.9861C100.277 82.9443 100.287 82.892 100.3 82.8292C100.338 82.7498 100.342 82.6745 100.313 82.6033C100.279 82.5531 100.284 82.5322 100.325 82.5406C100.434 82.4319 100.489 82.3232 100.489 82.2144L100.533 82.158C100.579 82.1455 100.613 82.087 100.634 81.9824C100.646 81.9197 100.669 81.8591 100.703 81.8005C100.757 81.7462 100.787 81.7086 100.791 81.6877L100.804 81.6249L100.735 81.6437L100.722 81.7064L100.691 81.7001L100.697 81.6687L100.722 81.5432C100.747 81.4178 100.777 81.3258 100.81 81.2672C100.819 81.2254 100.852 81.1669 100.911 81.0916L100.924 81.0289C100.873 81.0623 100.848 81.079 100.848 81.079C100.798 81.1124 100.66 81.2587 100.433 81.5178C100.375 81.593 100.32 81.6473 100.27 81.6807L100.264 81.7121C100.251 81.7748 100.199 81.8731 100.106 82.0069C100.018 82.1197 99.9661 82.218 99.9492 82.3016C99.9492 82.3016 99.9471 82.3121 99.9429 82.333C99.9429 82.333 99.9325 82.3309 99.9115 82.3267L99.9242 82.2639L100.107 81.8437C100.136 81.8061 100.142 81.7747 100.126 81.7496C100.134 81.7078 100.153 81.668 100.182 81.6304C100.216 81.5719 100.251 81.5029 100.289 81.4235C100.352 81.3273 100.39 81.2479 100.402 81.1851C100.407 81.1642 100.413 81.1328 100.421 81.091C100.455 81.0325 100.442 80.9864 100.384 80.9529L100.434 80.8651L100.441 80.8337L100.372 80.8525L100.334 80.8775L100.346 80.8148L100.629 80.3821L100.931 79.8553L100.944 79.7926C100.944 79.7926 100.934 79.7905 100.913 79.7863C100.913 79.7863 100.911 79.7967 100.906 79.8177C100.885 79.8134 100.873 79.8218 100.869 79.8427L100.793 79.8928L100.806 79.8301C100.831 79.8134 100.846 79.7946 100.85 79.7737C100.858 79.7318 100.875 79.7026 100.9 79.6859L100.913 79.6231L100.875 79.6482L100.473 80.1874L100.429 80.2438L100.391 80.2689L100.404 80.2061C100.412 80.1643 100.427 80.1455 100.448 80.1497C100.511 80.0535 100.565 79.9448 100.611 79.8236C100.678 79.7065 100.756 79.5915 100.844 79.4787L101.347 78.7639L101.913 77.8986L102.189 77.4973L102.485 77.0019L102.818 76.4814C102.906 76.3685 103.017 76.1951 103.152 75.9609C103.365 75.6558 103.491 75.4635 103.529 75.3841C103.659 75.1708 103.741 75.035 103.774 74.9764C103.854 74.7966 104.038 74.4747 104.328 74.0107C104.386 73.9354 104.453 73.8184 104.529 73.6595C104.684 73.4296 104.814 73.2164 104.919 73.0199C104.982 72.9237 105.036 72.815 105.082 72.6937C105.15 72.5767 105.227 72.4617 105.315 72.3489C105.432 72.1984 105.567 71.9643 105.718 71.6465L106.07 71.0319C106.108 70.9525 106.158 70.8647 106.221 70.7685C106.284 70.6724 106.34 70.5532 106.391 70.411C106.416 70.3943 106.422 70.363 106.41 70.3169C106.401 70.25 106.401 70.1956 106.41 70.1538C106.389 70.1496 106.381 70.137 106.385 70.1161C106.389 70.0952 106.391 70.0847 106.391 70.0847C106.462 70.0555 106.504 70.0095 106.517 69.9468C106.534 69.8631 106.544 69.8109 106.548 69.7899C106.561 69.7272 106.601 69.6917 106.668 69.6834C106.668 69.6834 106.731 69.6417 106.856 69.5581C107.074 69.3409 107.254 69.203 107.396 69.1446C107.673 69.0697 107.878 69.0239 108.012 69.0073L108.376 68.9827L109.009 69.2408C109.026 69.2659 109.066 69.2848 109.128 69.2974C109.275 69.3269 109.36 69.3877 109.385 69.4798L109.435 69.5551C109.452 69.5803 109.479 69.6075 109.517 69.6368C109.555 69.6662 109.588 69.7164 109.617 69.7876C109.613 69.8085 109.619 69.8315 109.636 69.8566C109.678 69.865 109.705 69.8923 109.717 69.9383C109.784 70.0388 109.809 70.1309 109.792 70.2145C109.792 70.4321 109.784 70.5827 109.767 70.6664L109.54 71.143C109.339 71.4942 109.177 71.7555 109.056 71.9269L108.855 72.2781L108.421 72.9741C108.308 73.1037 108.194 73.2876 108.081 73.5259C107.897 73.7935 107.769 73.9962 107.698 74.1342L107.522 74.3599C107.509 74.4226 107.488 74.4728 107.459 74.5104L107.182 74.9117L106.886 75.4071L106.308 76.3352L106.05 76.6424L105.805 77.05C105.713 77.1838 105.608 77.3259 105.491 77.4764C105.373 77.6268 105.239 77.8066 105.088 78.0156L104.523 78.7177L103.674 79.8526L102.932 80.7804L102.561 81.3259C102.498 81.4221 102.435 81.5182 102.373 81.6144C102.335 81.6938 102.299 81.7628 102.266 81.8213L101.857 82.3919L101.297 83.2259L100.995 83.7526C100.958 83.8321 100.97 83.8781 101.033 83.8908L101.052 83.9598C101.047 83.9807 101.018 84.0183 100.964 84.0727C100.934 84.1103 100.947 84.1563 101.001 84.2108C100.875 84.4031 100.812 84.5536 100.812 84.6624C100.808 84.6833 100.781 84.7105 100.731 84.7439L100.712 84.838L100.806 84.8569L100.824 84.926C100.803 85.0306 100.776 85.1121 100.743 85.1706C100.692 85.204 100.648 85.2061 100.611 85.1767ZM96.0015 87.4804L96.0642 87.493L96.0141 87.4176L95.9011 87.4928L95.9261 87.5305L96.0015 87.4804ZM96.3276 87.6439C96.3318 87.623 96.3235 87.6105 96.3026 87.6062L96.3152 87.5435L96.3215 87.5121L96.2588 87.4995C96.2503 87.5413 96.2336 87.5706 96.2085 87.5873C96.2419 87.6376 96.2586 87.6627 96.2586 87.6627L96.3276 87.6439ZM97.2928 88.6869C97.2718 88.6827 97.2509 88.6785 97.23 88.6743C97.2342 88.6534 97.2363 88.6429 97.2363 88.6429L97.1359 88.6554L97.1546 88.7244L97.2928 88.6869ZM97.1363 88.329C97.1405 88.3081 97.1635 88.3019 97.2054 88.3103L97.1489 88.2663C97.0862 88.2536 97.0423 88.2557 97.0171 88.2724C96.9962 88.2682 96.9816 88.287 96.9731 88.3288L97.0233 88.4042L97.1363 88.329ZM96.5034 87.5814C96.5243 87.5856 96.5599 87.571 96.6102 87.5376L96.5851 87.4999C96.5349 87.5333 96.5097 87.55 96.5097 87.55L96.5034 87.5814ZM96.372 87.2612L96.4036 87.1043C96.412 87.0625 96.4058 87.0395 96.3849 87.0353L96.3409 87.0917C96.3367 87.1126 96.3303 87.144 96.3219 87.1858C96.3177 87.2067 96.2926 87.2234 96.2466 87.2359L96.2716 87.2736C96.2883 87.2987 96.3176 87.3155 96.3594 87.3239L96.372 87.2612ZM96.8984 87.8894L96.9047 87.858L96.7919 87.77L96.7291 87.7574L96.7542 87.7951C96.7876 87.8453 96.8252 87.8747 96.867 87.8831L96.8984 87.8894ZM97.0559 87.4315L97.0622 87.4001C97.0664 87.3792 97.058 87.3666 97.0371 87.3624C96.9911 87.3749 96.9597 87.3686 96.943 87.3435C96.9054 87.3141 96.8636 87.3057 96.8175 87.3182C96.7924 87.3349 96.7777 87.3537 96.7735 87.3746C96.7735 87.3746 96.7986 87.4123 96.8487 87.4877L96.8801 87.494L96.9114 87.5003L97.0559 87.4315ZM96.636 86.9226C96.6445 86.8808 96.6612 86.8515 96.6864 86.8348L96.6676 86.7658L96.6363 86.7595L96.5923 86.8159L96.5984 86.9477L96.6234 86.9854L96.636 86.9226ZM97.0852 89.0695C97.0643 89.0653 97.0329 89.059 96.9911 89.0505C96.9701 89.0463 96.9744 89.0254 97.0037 88.9878C97.0288 88.9711 97.0309 88.9606 97.01 88.9564C97.0142 88.9355 97.0059 88.923 96.9849 88.9187C96.9682 88.8936 96.939 88.8768 96.8972 88.8684C96.8762 88.8642 96.8574 88.8495 96.8407 88.8244C96.824 88.7993 96.8282 88.7784 96.8534 88.7617L96.8786 88.6362C96.9331 88.5819 96.9185 88.5463 96.8348 88.5295C96.7093 88.5042 96.678 88.4435 96.7409 88.3473L96.7285 88.2469L96.6971 88.2406L96.6531 88.297C96.6656 88.3431 96.6488 88.3723 96.6028 88.3848C96.5777 88.4015 96.563 88.4203 96.5588 88.4412L96.5338 88.4036C96.538 88.3826 96.5317 88.3596 96.515 88.3345C96.5192 88.3136 96.4983 88.3094 96.4523 88.3219L96.4586 88.2905C96.4462 88.1357 96.3731 88.0666 96.2392 88.0831C96.2183 88.0789 96.1869 88.0726 96.1451 88.0642C96.1242 88.06 96.0949 88.0432 96.0573 88.0139C96.0406 87.9887 95.9904 87.9678 95.9068 87.9509C95.8231 87.9341 95.7897 87.8838 95.8065 87.8002L95.8886 87.3923L95.9013 87.3296L95.8825 87.2606L95.8385 87.317C95.8468 87.3839 95.8091 87.409 95.7255 87.3921C95.7255 87.3921 95.715 87.39 95.6941 87.3858C95.6941 87.3858 95.6962 87.3754 95.7004 87.3545L95.9019 86.8401L95.9901 86.5641C95.9985 86.5223 95.9902 86.4553 95.9653 86.3632C95.9528 86.3172 95.9758 86.2566 96.0345 86.1813L96.2543 86.0624L96.6059 85.9373C96.631 85.9206 96.6499 85.8809 96.6626 85.8181C96.6794 85.7345 96.736 85.6697 96.8322 85.6238C96.9661 85.6072 97.0916 85.6325 97.2087 85.6996C97.2672 85.7331 97.2629 85.8084 97.1959 85.9255L97.0447 86.352L97.0634 86.4211L97.1325 86.4024C97.1493 86.3187 97.1871 86.2393 97.2458 86.164C97.3002 86.1097 97.363 86.068 97.4342 86.0388C97.4593 86.0221 97.4656 86.0451 97.4529 86.1078L97.4466 86.1392L97.5157 86.1204L97.5597 86.064L97.591 86.0703L97.7102 86.127C97.752 86.1354 97.7855 86.1312 97.8106 86.1145L97.7542 86.0705C97.7208 86.0203 97.7355 86.0015 97.7982 86.0141C97.9614 85.9599 98.1643 85.979 98.4069 86.0714C98.4905 86.0882 98.5218 86.1489 98.5008 86.2535L98.4818 86.3476C98.4567 86.3643 98.4525 86.3852 98.4692 86.4103C98.4901 86.4146 98.511 86.4188 98.5319 86.423C98.578 86.4105 98.6073 86.4273 98.6197 86.4733C98.6574 86.5026 98.6866 86.5194 98.7075 86.5236L98.8642 86.7184L99.0019 87.0072L98.9956 87.0386C99.054 87.1809 99.01 87.2373 98.8636 87.2079C98.8217 87.1994 98.7966 87.2161 98.7882 87.258L98.7252 87.4085C98.675 87.4419 98.6645 87.4942 98.6937 87.5654C98.7187 87.6574 98.7478 87.7286 98.7813 87.7788L98.7749 87.8102L98.7122 87.7976L98.6871 87.7599C98.6286 87.7264 98.5847 87.7284 98.5553 87.766L98.549 87.7974C98.5448 87.8183 98.528 87.8476 98.4987 87.8852C98.4694 87.9228 98.4317 87.9478 98.3857 87.9603C98.3605 87.977 98.3291 88.0251 98.2913 88.1046C98.2787 88.1673 98.2786 88.2217 98.2911 88.2677L98.2848 88.2991C98.2806 88.32 98.2534 88.3472 98.2031 88.3806C98.1529 88.414 98.1423 88.4663 98.1715 88.5374L98.1652 88.5688C98.0983 88.5771 98.092 88.6085 98.1463 88.6629C98.1463 88.6629 98.1442 88.6734 98.14 88.6943C98.1609 88.6985 98.1609 88.6985 98.14 88.6943C98.1231 88.7779 98.0791 88.8344 98.008 88.8636C98.0038 88.8845 97.964 88.92 97.8886 88.9701C97.8426 88.9826 97.7965 88.9951 97.7505 89.0076C97.7044 89.0201 97.6563 89.043 97.606 89.0764C97.4846 89.139 97.3549 89.1347 97.217 89.0634L97.0852 89.0695ZM97.283 86.4653C97.3124 86.4277 97.3396 86.4005 97.3647 86.3838C97.394 86.3462 97.4129 86.3065 97.4213 86.2647L97.4026 86.1956L97.39 86.2584L97.3773 86.3211L97.2893 86.4339L97.283 86.4653ZM98.9524 86.4423C98.9315 86.4381 98.9127 86.4235 98.896 86.3983C98.8793 86.3732 98.8751 86.3397 98.8835 86.2979C98.9087 86.2812 98.9191 86.2833 98.9149 86.3042C98.9567 86.3126 99.0153 86.3462 99.0905 86.4049L98.9524 86.4423ZM99.508 83.8449C99.4746 83.7946 99.4621 83.7486 99.4705 83.7068C99.4496 83.7026 99.4433 83.6795 99.4517 83.6377L99.5145 83.6504L99.621 83.7697C99.6377 83.7948 99.6774 83.8137 99.7402 83.8264C99.7402 83.8264 99.7506 83.8285 99.7716 83.8327C99.7673 83.8536 99.7548 83.8619 99.7339 83.8577L99.5644 83.8889L99.508 83.8449ZM100.942 81.4243L101.08 81.2236L101.087 81.1923L101.055 81.186L100.917 81.3866C100.896 81.3824 100.883 81.3907 100.879 81.4117C100.9 81.4159 100.911 81.418 100.911 81.418L100.942 81.4243ZM100.585 80.7649C100.627 80.7733 100.65 80.7671 100.654 80.7461C100.683 80.7085 100.7 80.6793 100.704 80.6583L100.711 80.627L100.635 80.6771L100.591 80.7335C100.57 80.7293 100.558 80.7377 100.554 80.7586L100.585 80.7649ZM100.861 80.5268C100.828 80.4765 100.811 80.4514 100.811 80.4514C100.807 80.4723 100.78 80.4995 100.73 80.5329L100.723 80.5642L100.861 80.5268ZM102.739 79.4685L102.721 79.3995L102.639 79.481L102.626 79.5437L102.739 79.4685ZM104.267 77.2301C104.288 77.2343 104.301 77.2259 104.305 77.205C104.313 77.1632 104.338 77.1465 104.38 77.1549C104.401 77.1591 104.416 77.1403 104.424 77.0985L104.399 77.0608C104.378 77.0566 104.355 77.0628 104.33 77.0795C104.305 77.0962 104.309 77.0753 104.343 77.0168L104.311 77.0105C104.294 77.0941 104.271 77.1547 104.242 77.1924L104.267 77.2301Z\" fill=\"#2D2C78\"><\/path><path d=\"M19.251 159.836L19.4233 159.644C19.4314 159.684 19.3985 159.731 19.251 159.836Z\" fill=\"#2D2C78\"><\/path><path d=\"M65.3525 118.307C65.3525 118.307 65.3806 118.278 65.4038 118.267C65.3942 118.301 65.3525 118.307 65.3525 118.307Z\" fill=\"#2D2C78\"><\/path><path d=\"M26.112 152.659C26.0944 152.653 26.0721 152.665 26.0498 152.677L26.1295 152.664L26.112 152.659Z\" fill=\"#2D2C78\"><\/path><path d=\"M15.5562 158.661C18.465 157.149 19.0314 156.404 22.085 154.936C22.7719 154.527 23.513 154.134 24.2361 153.736C24.9592 153.338 25.6822 152.94 26.3823 152.554C27.2045 152.429 28.1306 151.457 29.0282 151.205L29.2218 150.872C29.5424 150.782 29.8596 150.635 30.0697 150.38L30.0154 150.364C30.474 150.204 30.8502 149.85 31.0885 149.773L31.0342 149.756L31.514 149.453L31.3956 149.455C32.1533 149.142 32.8055 148.648 33.3657 148.201L33.4433 148.411C34.5535 147.345 35.2822 147.341 36.2147 146.278L36.1604 146.262C37.0547 145.953 37.5342 145.444 38.0136 144.935C38.2649 144.674 38.4931 144.426 38.7987 144.182C38.9514 144.06 39.0993 143.955 39.2883 143.844C39.4592 143.728 39.6613 143.639 39.8684 143.534C39.6432 143.634 39.8715 143.385 39.8172 143.369C40.5056 142.886 41.2087 142.351 41.4986 142.644C41.9667 142.244 41.794 142.229 41.7428 142.064C41.8631 142.194 42.3149 141.919 42.6812 141.6L42.4609 141.683L43.5303 140.829L43.5672 141.251C44.0384 140.703 43.4169 140.814 43.9804 140.423L44.1764 140.632C44.8694 139.926 44.9983 139.199 45.5382 138.41C45.8913 138.068 46.2493 137.709 46.6254 137.356C47.0015 137.002 47.3727 136.666 47.762 136.335C48.5274 135.651 49.2747 134.962 50.0401 134.278C50.7874 133.588 51.5034 132.87 52.1651 132.136C52.8268 131.402 53.4161 130.646 53.933 129.868L53.8701 129.607C53.6658 129.358 54.9089 129.136 54.7604 128.829L55.1613 128.596C55.1957 128.475 55.3055 128.228 55.1116 128.356C55.3595 128.039 55.4089 128.073 55.6718 127.909L55.7994 127.462C56.2227 126.805 56.712 126.262 57.2326 125.747C57.7581 125.214 58.2655 124.677 58.7349 123.996C58.9447 123.537 59.2828 123.041 59.6586 122.482C60.0295 121.94 60.4694 121.363 60.9093 120.787L61.2458 120.365C61.3624 120.232 61.4658 120.077 61.5823 119.944C61.8023 119.655 62.0355 119.389 62.2505 119.118C62.6806 118.576 63.1091 118.107 63.4276 117.681C63.9448 117.108 64.3681 116.452 64.7651 115.75C65.1439 115.042 65.4783 114.284 65.8259 113.548L66.0833 112.991L66.3226 112.428C66.4898 112.049 66.6701 111.692 66.8554 111.319C67.0358 110.962 67.2342 110.611 67.4508 110.266C67.6493 109.915 67.8791 109.592 68.122 109.292C68.1334 109.183 68.342 109.003 68.3782 109.014C68.5963 108.594 68.8144 108.175 69.0144 107.749L69.6326 106.479C69.6326 106.479 69.7276 106.284 69.8933 105.979C70.059 105.674 70.2869 105.22 70.5296 104.714C70.7903 104.213 71.0658 103.662 71.3594 103.115C71.4348 102.988 71.5152 102.845 71.5907 102.718C71.6661 102.591 71.7465 102.448 71.8039 102.315C71.9548 102.062 72.0876 101.803 72.2287 101.584C72.7849 100.669 73.307 100.08 73.5739 100.384C73.7074 100.537 73.777 100.913 73.7583 101.598C73.7424 101.93 73.72 102.353 73.655 102.856C73.6225 103.108 73.5851 103.377 73.5427 103.663C73.5004 103.949 73.4301 104.264 73.3731 104.602L73.4602 104.572C73.2081 105.318 72.977 105.92 72.7065 106.455C72.4408 106.972 72.1224 107.399 71.7316 107.804C72.0429 108.16 71.1972 108.988 71.1484 109.365L71.1944 109.342C70.4471 110.031 70.4999 111.224 69.7986 111.89C69.8447 111.867 69.9664 111.922 70.0796 111.732C69.7038 112.291 69.1507 113.058 69.3434 113.21C69.1268 113.556 68.9004 113.935 68.6691 114.333C68.4378 114.73 68.1884 115.121 67.9439 115.496C67.4549 116.245 66.9675 116.919 66.519 117.251L66.6242 117.227C66.0705 117.582 66.1745 117.838 65.6999 118.33C65.7082 118.37 65.6934 118.421 65.7115 118.427C65.4207 118.619 65.1713 119.011 64.9219 119.402C64.6774 119.777 64.451 120.157 64.2605 120.342L64.3857 120.455L63.6357 121.498L63.8718 121.084C63.6365 121.013 63.5629 121.271 63.4516 121.592C63.3583 121.919 63.1813 122.332 62.7837 122.623C62.5622 122.986 62.1021 123.22 61.6649 123.443C61.4348 123.561 61.2229 123.683 61.0471 123.817C60.8664 123.968 60.7038 124.124 60.6219 124.342C60.1847 124.565 61.1382 124.256 60.6109 124.657C60.8035 124.808 60.91 124.504 60.9729 124.766C60.4949 125.201 60.5385 125.737 59.9357 126.265L60.0741 126.4C59.1786 126.989 59.0749 128.041 58.3895 128.375C57.6143 129.094 58.3892 129.272 57.3934 129.868L57.3153 130.349C57.0478 130.735 56.8631 130.417 56.6121 130.883C56.7471 130.961 56.2907 131.459 56.6029 131.329C56.3143 131.858 55.851 132.241 55.3682 132.693C54.8902 133.128 54.3926 133.631 54.0187 134.322C53.5533 134.368 53.1613 135.053 52.8192 135.08C52.9033 135.199 51.7617 136.236 52.5768 135.791C52.6459 135.756 52.7345 135.652 52.6851 135.619L52.8842 135.679C52.7253 136.098 52.3968 136.353 52.0551 136.586C51.7133 136.819 51.3403 137.024 51.0513 137.348C51.1924 137.129 51.4387 136.886 51.1822 136.958L50.6371 137.559L50.8789 137.539C50.6129 137.851 50.3469 138.163 50.0859 138.457L50.0592 138.206C49.7079 138.679 49.7957 139.061 49.107 139.338C48.7815 139.446 49.3281 138.77 48.8238 139.159C48.5759 139.477 48.2805 139.892 47.9489 140.296C47.6173 140.7 47.2626 141.116 46.8997 141.492C46.8221 141.282 46.6135 141.462 46.3917 141.619L46.5021 141.783C45.521 142.327 46.4997 142.343 45.5499 142.915L45.7128 142.964L45.2324 142.857C44.2412 143.23 45.11 143.492 43.9559 143.816C44.3025 143.566 43.8237 143.384 43.4921 143.788L43.7092 143.854C43.4743 143.988 43.3509 144.007 43.2295 144.157C43.435 144.126 43.4862 144.29 43.1215 144.535L43.4998 144.519L42.6564 144.787C42.3036 145.334 41.3931 145.769 41.3674 146.135C41.3674 146.135 40.3967 147.056 39.9691 147.039C40.2931 147.006 39.7543 147.515 40.0455 147.529C39.6525 147.597 38.7404 148.106 38.5453 148.514L38.6325 148.484C38.084 149.028 37.517 149.361 36.9731 149.683C36.4292 150.004 35.8902 150.308 35.4157 150.8C35.338 150.59 34.8174 151.105 34.7922 150.78C34.4569 150.921 34.1842 151.119 33.9477 151.328C33.6931 151.531 33.4977 151.734 33.289 151.914C32.8948 152.261 32.535 152.489 32.0791 152.295C31.5171 152.611 31.5751 152.89 31.3205 153.093L31.4717 153.046C30.4167 153.642 30.1127 153.812 29.3783 154.319C28.9559 154.49 28.6792 154.219 28.05 154.702C28.3641 154.703 28.0699 154.839 27.807 155.002C27.9862 154.925 28.0635 154.93 27.7843 155.219C27.7119 155.197 27.6248 155.227 27.5377 155.257C27.5377 155.257 27.5279 155.291 27.546 155.297C27.0907 155.514 27.1382 155.416 27.314 155.283C27.2959 155.277 27.2876 155.237 27.3303 155.157C27.0069 155.601 26.0814 155.882 26.1805 156.154C25.5132 156.495 24.9117 156.743 24.315 156.973C24.0257 157.091 23.7413 157.192 23.452 157.31C23.1627 157.428 22.8784 157.529 22.5891 157.647C22.5351 157.837 22.859 157.804 23.2125 157.668L22.3989 158.038C22.5093 158.202 22.9118 157.894 23.1732 157.805C22.7873 158.193 22.2596 158.388 21.7138 158.578C21.1681 158.769 20.5993 158.97 20.1263 159.388L19.817 159.369L19.7612 159.427C19.7216 159.359 19.4207 159.38 19.2464 159.44C19.1826 159.663 19.4624 159.785 18.897 160.044C18.7246 160.235 18.3942 160.359 18.0457 160.478C17.6792 160.591 17.2994 160.682 16.9969 160.777C17.3009 160.608 17.1561 160.564 16.9735 160.583C16.7024 160.707 16.6155 160.942 16.3689 160.98L16.4465 161.19C16.456 160.95 15.6014 161.327 15.4566 161.283C15.3928 161.507 15.9498 161.208 16.0848 161.286C14.959 161.787 15.5194 161.545 14.3804 162.023C13.6997 162.135 14.3899 161.783 14.0132 161.725C13.4674 161.915 12.8738 161.997 12.3284 162.393L12.4069 162.118C11.358 162.418 10.7564 162.665 10.1683 163.142C9.14401 163.355 8.31847 163.423 7.68865 163.495C7.06375 163.549 6.61311 163.543 6.29068 163.502C5.66393 163.424 5.61421 163.185 5.80625 162.926C6.19524 162.389 7.61684 161.679 7.61684 161.679C8.31199 161.31 8.91513 160.988 9.51671 160.74C10.1183 160.492 10.7051 160.296 11.3101 160.105C12.5118 159.684 13.8435 159.358 15.5528 158.604L15.5562 158.661Z\" fill=\"#2D2C78\"><\/path><path d=\"M10.0974 153.707L10.1455 153.815C10.1094 153.804 10.0829 153.759 10.0974 153.707Z\" fill=\"#2D2C78\"><\/path><path d=\"M11.0359 157.692C11.0359 157.692 11.0359 157.692 11.054 157.698L11.0493 157.714L11.0359 157.692Z\" fill=\"#2D2C78\"><\/path><path d=\"M12.6637 154.184C12.2793 155.131 12.5045 155.572 11.8384 156.414C11.6128 156.868 11.2618 157.284 10.9694 157.698C10.5854 157.749 10.6382 158.25 10.2575 158.358L10.3619 158.539C10.235 158.575 10.1211 158.634 10.1588 158.776L10.2125 158.792C10.0222 158.846 10.0094 159.029 9.90526 159.053L9.95901 159.07L9.84363 159.202L9.91529 159.224C9.66481 159.353 9.52514 159.572 9.46199 159.795L9.28436 159.666C9.22819 160.209 8.75274 160.101 8.76002 160.626L8.81375 160.642C8.03102 160.796 8.66376 161.586 7.89409 161.761C7.99823 161.737 7.96908 161.84 8.01797 161.874C7.82942 162.059 7.63602 162.261 7.27593 162.021C7.17361 162.176 7.299 162.215 7.42287 162.327C7.27622 162.226 7.11682 162.308 7.02422 162.429L7.1235 162.422C7.11378 162.457 7.06825 162.48 7.04548 162.492L6.99993 162.515L6.92191 162.585C6.82415 162.518 6.72637 162.45 6.6286 162.383C6.64348 162.537 6.9984 162.589 6.86663 162.643L6.58002 162.555C6.56059 162.624 6.64865 162.725 6.76433 162.798C6.88 162.871 7.05912 162.925 7.16175 162.975C7.14231 163.044 7.06428 163.113 6.91794 163.218C6.77159 163.323 6.57972 163.451 6.40088 163.601C6.45311 163.692 6.7543 163.728 7.15447 163.551L7.3837 163.36C7.53976 163.221 7.43411 163.319 7.36428 163.429C7.27653 163.533 7.2067 163.642 7.33999 163.515C7.32541 163.566 7.29291 163.612 7.28319 163.647C7.33845 163.589 7.40677 163.554 7.4262 163.485C7.46688 163.479 7.41647 163.519 7.39218 163.605C7.44744 163.547 7.50271 163.49 7.54006 163.426C7.636 163.362 7.65725 163.425 7.71919 163.481C7.71919 163.481 7.7453 163.526 7.76321 163.532C7.81696 163.548 7.88861 163.57 7.94235 163.586C8.06774 163.625 8.19314 163.663 8.3331 163.65C9.00653 163.332 10.1989 163.864 10.8732 164.163C11.7938 164.761 13.0814 163.717 14.0314 164.417C14.0639 164.371 14.1471 164.489 14.1374 164.524L15.0588 164.637C15.0588 164.637 16.1774 164.81 16.8177 165.229C17.458 165.648 17.6071 166.291 15.7626 167.24L15.779 167.32C15.2729 167.389 14.9489 167.365 14.6684 166.981C14.5567 167.376 14.2679 166.952 14.1216 167.057L14.1119 167.091C13.8671 166.718 13.4822 167.254 13.2277 166.915C13.218 166.949 13.2247 167.063 13.2963 167.085C13.0862 167.002 12.8142 166.863 12.769 167.092C12.2674 166.939 11.5642 166.949 11.2755 166.525L11.2967 166.587C11.1449 166.298 11.0638 166.516 10.878 166.348C10.8683 166.382 10.8634 166.399 10.8586 166.416C10.684 166.139 10.2708 166.293 10.1339 166.158L10.0901 166.313L9.70425 166.232L9.86211 166.224C9.8533 165.774 9.52388 166.457 9.26459 166.136C8.98466 166.162 8.8025 165.155 8.49675 165.342C8.38411 165.121 8.59329 165.688 8.39442 165.497C8.3671 165.731 8.4679 165.65 8.41932 165.822C8.22379 165.688 8.0729 166.015 7.85126 165.835L7.80268 166.007C7.79449 165.967 7.74559 165.934 7.70976 165.923C7.69185 165.917 7.67395 165.912 7.65604 165.906C7.63812 165.901 7.60229 165.89 7.58438 165.884C7.47204 165.869 7.36791 165.893 7.24585 165.912C7.01966 165.955 6.79831 165.981 6.68901 165.817C6.48377 165.717 6.33257 165.839 6.17317 165.921C6.03168 166.008 5.85922 166.067 5.69618 165.887C5.55955 165.957 5.42293 166.028 5.2863 166.098C4.9933 166.102 5.36887 165.806 4.97508 165.891C4.85484 166.041 4.50477 165.972 4.54242 166.114C4.09489 166.183 3.81314 166.078 3.54444 165.996C3.25783 165.909 2.97121 165.821 2.21125 165.963C2.3494 165.818 2.25983 165.791 2.15235 165.758C2.04487 165.725 1.93738 165.693 2.06095 165.6C1.95195 165.641 1.79408 165.649 1.64106 165.64C1.69783 165.508 1.77252 165.381 1.27823 165.753C1.22783 165.794 1.19533 165.84 1.2181 165.828C1.2181 165.828 1.2588 165.822 1.28158 165.81L1.00347 165.968C0.944868 165.968 0.899305 165.992 0.858621 165.998C0.765714 165.914 1.00953 165.671 1.2843 165.456C1.56394 165.224 1.87939 165.003 1.96866 164.825C1.98505 164.905 1.84205 165.066 2.12502 164.891L2.33452 164.563L2.0385 164.716L2.29658 164.216L2.52611 164.23C2.55526 164.127 2.4575 164.06 2.44111 163.98C2.42471 163.901 2.49453 163.791 2.79542 163.622C2.95482 163.54 2.99885 163.59 3.02982 163.619C3.0787 163.652 3.11453 163.663 3.24782 163.536C3.31249 163.238 3.45823 162.723 3.73422 162.228C3.94432 162.311 4.01902 162.185 4.14745 162.075L3.96832 162.02C4.58466 161.629 3.68624 161.71 4.25856 161.269L4.10555 161.259C4.25858 161.269 4.4116 161.278 4.55977 161.305C4.86885 161.175 4.81662 161.084 4.80994 160.97C4.81479 160.953 4.8066 160.913 4.79355 160.891C4.79355 160.891 4.80326 160.856 4.80812 160.839C4.81784 160.805 4.8992 160.792 5.05223 160.802C4.95143 160.883 5.36192 161.083 5.37468 160.9L5.19554 160.845C5.27357 160.776 5.36313 160.803 5.36465 160.729C5.25231 160.713 5.12843 160.601 5.22923 160.52L4.99637 160.449L5.4017 160.46C5.33946 160.199 5.70229 160.085 5.5441 159.888C5.5441 159.888 5.65583 159.493 5.9473 159.563C5.75845 159.543 5.82161 159.319 5.62456 159.259C5.84924 159.291 6.15012 159.121 6.03748 158.9L6.00164 158.889C6.05629 158.421 6.66019 158.418 6.65625 157.95C6.83386 158.079 6.84329 157.84 7.04216 158.031C7.49273 157.814 6.95774 157.091 7.78024 157.416C7.91839 157.272 7.72773 157.12 7.73897 157.012L7.6755 157.03C7.92417 156.77 7.97123 156.672 8.09298 156.448C8.22961 156.378 8.58636 156.561 8.61855 156.31C8.44761 156.295 8.52565 156.225 8.56785 156.145C8.51745 156.185 8.4637 156.169 8.43091 156.01C8.48465 156.026 8.52533 156.02 8.5481 156.008C8.5481 156.008 8.5302 156.003 8.51228 155.997C8.63586 155.904 8.66196 155.95 8.64253 156.018C8.66045 156.024 8.69627 156.035 8.71752 156.097C8.60974 155.859 8.93675 155.735 8.72816 155.578C9.00112 155.232 9.40948 155.095 9.68091 154.823C9.57495 154.716 9.43014 154.747 9.33419 154.811L9.50968 154.603C9.34026 154.514 9.33236 154.68 9.25919 154.732C9.12833 154.3 9.85763 154.336 9.77717 153.864L9.9481 153.879L9.95294 153.861C10.0067 153.878 10.1418 153.882 10.1922 153.841C10.0553 153.706 9.83547 153.658 9.91987 153.497C9.84306 153.287 10.1831 153.185 10.3571 153.052C10.3279 153.155 10.4403 153.17 10.5216 153.158C10.5638 153.077 10.4448 152.948 10.549 152.923L10.3486 152.806C10.5262 152.935 10.6707 152.699 10.7782 152.732C10.6413 152.597 10.5878 152.786 10.4445 152.742C10.6312 152.426 10.5468 152.587 10.7336 152.271C10.9743 152.176 10.9112 152.399 11.1407 152.413C11.2561 152.281 11.492 152.203 11.4428 151.964L11.5977 152.105C11.8903 151.896 11.9438 151.707 11.8506 151.417C13.1404 150.709 13.7282 150.833 13.9874 151.154C14.2467 151.476 14.1823 151.979 14.1823 151.979C14.1693 153.057 13.3948 153.25 12.7174 154.2L12.6637 154.184Z\" fill=\"#2D2C78\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-41cfb5c e-con-full e-flex e-con e-parent\" data-id=\"41cfb5c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4e28675 e-con-full e-flex e-con e-child\" data-id=\"4e28675\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-572c5d6 elementor-widget elementor-widget-image\" data-id=\"572c5d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"885\" height=\"929\" src=\"https:\/\/arthroseactive.be\/wp-content\/uploads\/2025\/12\/Rectangle-133.webp\" class=\"attachment-full size-full wp-image-4013\" alt=\"\" srcset=\"https:\/\/arthroseactive.be\/wp-content\/uploads\/2025\/12\/Rectangle-133.webp 885w, https:\/\/arthroseactive.be\/wp-content\/uploads\/2025\/12\/Rectangle-133-286x300.webp 286w, https:\/\/arthroseactive.be\/wp-content\/uploads\/2025\/12\/Rectangle-133-768x806.webp 768w\" sizes=\"(max-width: 885px) 100vw, 885px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5be3ada e-con-full e-flex e-con e-child\" data-id=\"5be3ada\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5985651 elementor-widget elementor-widget-spacer\" data-id=\"5985651\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e8db0fe elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"e8db0fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Over ons<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aacbdb3 elementor-widget elementor-widget-text-editor\" data-id=\"aacbdb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Artrose Active is een redactioneel platform van KiOmed Pharma, een Belgisch bedrijf dat zich inzet voor onderzoek naar en de ontwikkeling van innovatieve oplossingen voor degeneratieve aandoeningen.<\/p><p> <\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">We hebben dit platform ontwikkeld om beweging weer centraal te stellen in de aanpak van knieartrose. Pijn leidt vaak tot vermijdingsgedrag, en dat vermijdingsgedrag voedt een vicieuze cirkel van sedentair gedrag en verlies van mobiliteit. <\/p><p> <\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Op onze schaal willen wij ook bijdragen aan een andere kijk op artrose: anders informeren, lichaamsbeweging en de verschillende zorgtrajecten ten volle hun plaats geven, en bepaalde Belgische wetenschappelijke innovaties zichtbaar maken \u2013 waaronder CM-chitosan, dat wij ontwikkelen. Een aanpak die aansluit bij die van andere ge\u00ebngageerde actoren: wetenschappelijke verenigingen, pati\u00ebntenverenigingen, onderzoeksteams en zorgverleners. <\/p><p> <\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Wij richten ons in eerste instantie op knieartrose. Andere lokalisaties (heup, handen) kunnen in de toekomst aan bod komen. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8b3cf08 e-con-full e-flex e-con e-child\" data-id=\"8b3cf08\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dacabaa elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"dacabaa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><a href=\"#\">Een initiatief van <\/a><\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb218b1 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"fb218b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"136\" height=\"92\" src=\"https:\/\/arthroseactive.be\/wp-content\/uploads\/2025\/12\/logo-kiomed-colored.svg\" class=\"attachment-full size-full wp-image-4014\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c439592 e-con-full e-flex e-con e-parent\" data-id=\"c439592\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-e8a5bf6 e-con-full e-flex e-con e-child\" data-id=\"e8a5bf6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-54b758f elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"54b758f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wat ons dagelijks inspireert<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-163a383 elementor-absolute elementor-hidden-mobile elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"163a383\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Calque_2\" data-name=\"Calque 2\" viewBox=\"0 0 177.04 71.64\"><defs><style>      .cls-1 {        fill: #2d2c78;      }    <\/style><\/defs><g id=\"Calque_1-2\" data-name=\"Calque 1\"><path class=\"cls-1\" d=\"M4.46,45.82l-.28.06h-.16s-.32.04-.32.04c-.19.04-.36.04-.53-.02,0,0-.04-.02-.11-.07l-.08-.08c-.09,0-.2-.03-.35-.09-.14-.04-.26-.09-.36-.15l-.35-.25s-.04-.05-.05-.09c-.03-.02-.04-.03-.04-.06,0-.02-.02-.03-.04-.02l-.35-.41c-.12-.15-.21-.31-.27-.5-.07-.2-.1-.33-.11-.37-.03-.02-.04-.05-.05-.09,0-.02-.02-.03-.04-.02-.02,0-.04-.01-.04-.06l-.04-.06v.06s.02.03.02.03v.03s-.01-.03-.03-.02l-.06-.28h.03c-.08-.16-.13-.28-.14-.37l-.18-.68-.09-.41v-.03c-.09-.07-.14-.16-.16-.26,0-.11,0-.18-.02-.23-.04-.3-.09-.75-.13-1.35,0-.11,0-.33.02-.66,0-.18-.02-.3-.08-.38-.04-.08-.05-.17-.03-.29,0-.2.02-.5.07-.9l.12-.49s.02-.05.02-.07c0-.04,0-.08.01-.1l.04-.4.05-.24c.06-.21.12-.46.16-.76.01-.05.04-.21.09-.48l.15-.69s0-.11,0-.19l.02-.07c.11-.18.18-.34.19-.5.02-.11.06-.21.13-.29l.04-.14.41-.81c.07-.17.22-.39.45-.65l.5-.73.31-.36c.16-.15.32-.27.48-.37.22-.18.39-.3.51-.37l.33-.27c.14-.16.31-.25.5-.27.07,0,.17,0,.32-.04.16-.08.28-.13.36-.14.15-.03.24-.15.28-.36l.05-.24h.06s.13,0,.13,0c.13,0,.21.05.24.18l.05.09.18.22.07.02.2.15.04.02c-.03.05-.03.09,0,.13.05.03.08.06.08.08,0,.02.02.03.04.02.02,0,.03,0,.04.02.03-.05.04-.1.04-.14,0-.04-.02-.06-.04-.06.02,0,.03,0,.03,0,.02-.03.04-.03.06-.01.18,0,.33.02.47.03l.07.02c.07.03.12.02.16-.03.02-.03.04-.03.06-.01.02,0,.04,0,.06-.01h.06c.08-.03.17-.03.26,0,.02,0,.06,0,.11.04.02,0,.03,0,.04.02.02,0,.02,0,0,.03l.07.02s.04.02.04.02c.02-.03.04-.03.06-.01,0,.02.04.02.1.01.02,0,.03-.03.02-.07-.02,0-.03,0-.04-.02.02,0,.03,0,.04.02l.18.06.34.19c.12.06.23.15.32.26.01.06.06.11.13.14.07,0,.14.07.2.18v.03c.15.06.26.09.32.1.03.02.04.01.03,0,.02-.03.03-.04.06-.04h.06s.03.09.13.15c.05.03.08.05.08.05.05.03.07.03.06-.01h.03s.16.25.16.25l.12.24c.15.21.27.49.35.84.03.13.09.33.2.61.03.15.04.25.04.32.02.08.03.19.04.32.03.13.04.28.03.45.01.15,0,.29,0,.43,0,.13.02.27.03.42-.02.03-.02.06-.01.1.03.02.03.04.01.06,0,.11,0,.24-.01.4-.01.13-.03.28-.04.43-.01.13-.01.25.01.36.02.08.01.15-.02.2,0,.02,0,.03-.02.04,0,0,0-.01,0-.03-.03-.02-.05-.01-.06.01,0,0,0,.01,0,.03l-.09.48c-.04.12-.08.29-.12.52l-.05.21-.12.35-.11.42-.31.69c-.03.07-.06.16-.11.25-.02.09-.06.2-.1.32-.02,0-.03.02-.02.04,0,.02,0,.03,0,.03l.09-.02.11-.09-.04.14c0,.07-.05.11-.14.13-.16.06-.29.21-.39.45l-.02.07v.06c.03.06,0,.17-.05.31-.02.11-.13.36-.33.73l-.58.81c-.15.23-.25.37-.3.43-.07.08-.15.18-.23.31s-.14.23-.16.3c-.02.03-.02.06-.01.1,0,.02,0,.04-.02.07v.06s-.16.56-.16.56c-.04.1-.12.14-.24.12-.08-.05-.16-.07-.25-.08h-.03c-.05.08-.1.19-.16.34-.15.23-.24.45-.28.65l-.02.04s-.03,0-.03,0c0-.02,0-.03,0-.03h-.03s-.09.19-.09.19c-.01.05-.03.06-.06.04-.14-.06-.23-.01-.27.12l-.02.07c-.03.05-.08.07-.15.07-.05-.03-.12-.03-.19,0l-.31.1-.38.05s-.05.01-.09.02c-.04,0-.08.04-.11.09,0,.02,0,.03-.02.04l-.67.08ZM2.66,44.32l-.08-.08h-.03s.12.11.12.11v-.03ZM2.87,44.24c-.05-.03-.08-.05-.08-.05h-.03s.11.08.11.08v-.03ZM1.96,43.68s.07-.03.09-.05h-.1s-.06.03-.06.03l.07.02ZM2.2,43.73s-.02-.06-.04-.06c-.02,0-.04,0-.06.01h-.03s0,.04,0,.04c.02,0,.03,0,.03,0l.07.02s0,.03,0,.03c.02,0,.03,0,.03,0v-.03ZM3.39,44.68c.06-.03.15-.07.27-.09v.03s.18-.1.18-.1c.02,0,.03,0,.03,0,0-.02,0-.03,0-.03t0,0s0-.03,0-.03c-.05-.01-.08,0-.09.02-.02.03-.04.03-.06.01,0,.09-.04.11-.12.06l-.22.05-.16.03-.02.07h.06s.06-.03.06-.03l.07.02ZM3,44.21l.04.02.02-.04h-.03s-.03-.02-.07-.01h-.06s.03.02.04.04l.07.02v-.03ZM1.4,43.22l-.04-.02v.06s.06.06.06.06l-.04-.02c-.06-.05-.07-.09-.06-.12t0,0s0-.03,0-.03l-.16-.26s-.03,0-.04-.02c0,.04.01.06.01.06l.06.12v.06s0-.03-.02-.02c0-.02-.02-.03-.04-.02v.03s.01.03.01.03c.03.04.06.07.09.11.03.04.07.07.12.1,0,.02.03.03.07.02,0,.02.03.03.07.02h.03s-.13-.14-.13-.14ZM3.38,44.16l.06-.04-.09-.11s-.05.02-.09.05c-.02.03-.02.06-.01.1l.04.02.09-.02ZM2.72,43.71s.03-.02.02-.04c0-.02,0-.02.03,0l.07.02h.06s-.02-.04-.04-.04l-.07-.02h.06s.02-.02.06-.03l.08-.08c.03-.05.06-.06.09-.02h.03s-.02-.04-.04-.03c-.03-.06-.09-.06-.16,0-.02.03-.05.04-.09.05l-.29.03s-.05.03-.08.08h-.03s-.06.02-.06.02l-.09.02h-.03s0,.04,0,.04c.02,0,.03,0,.03,0,.03.02.06.02.1.01.04,0,.08,0,.1.01s.05.02.07.02c.04-.03.07-.05.09-.05,0-.02,0-.03,0-.03.02,0,.03,0,.04.02,0,.02,0,.03,0,.03.02,0,.03,0,.03,0ZM3.12,43.56s.06-.01.06-.01c.06-.01.1-.03.12-.06,0,0,.02-.03.05-.08l-.08-.05-.09.05h-.03s0,.04,0,.04c.05.03.06.05.01.06l-.06.04ZM3.66,43.35s.03-.02.02-.04l-.07-.02-.06.04-.02.04s-.01,0-.03,0c0,0,0,.01,0,.03h.03s.12-.07.12-.07ZM4.38,44.24c.28-.21.46-.35.53-.41.13-.09.23-.21.28-.36.02,0,.03-.02.02-.04h-.03c-.03.06-.09.11-.16.17,0,.02,0,.03-.02.04,0,.02,0,.03-.02.04,0,.02-.01.04-.06.04,0,.04-.02.07-.08.08l-.07-.02.04.06v.03s-.02,0-.02,0l-.13.03v.03s-.07.03-.11.06c-.04.03-.07.04-.09.02h-.06s0,.04,0,.04c.03.02.03.04.01.06,0,0-.01,0-.03,0-.04,0-.07.03-.09.05-.1.02-.18.08-.22.18,0,0,0,.01,0,.03,0,0,.01,0,.03,0l.26-.16ZM3.99,43.83c.03-.05.07-.06.13-.03l.06-.04-.07-.02.06-.04.07.02s.06-.02.06-.04c0-.02,0-.03.02-.04h.03s0-.04.02-.04c.06-.01.11-.05.14-.1l.06-.04v.03s.2-.17.2-.17l.11-.09-.02-.09-.06.04-.17.13c-.03.05-.11.11-.22.18-.12.07-.2.13-.25.19l-.17.13s-.03.02-.02.04h.03ZM4.2,42.97v-.03c-.07.01-.12.04-.16.07v.03s.04,0,.04,0l.12-.06ZM7.82,44.41c-.05-.03-.08-.05-.08-.05,0,0,.02-.03.05-.08,0,.02.03.05.08.08l-.06.04ZM5.73,43.09l.1-.12.02-.04h-.03s-.14.13-.14.13v.03s.04,0,.04,0ZM5.22,42.84s.03-.02.02-.04c0-.02,0-.03.02-.04l.07-.11s.05-.04.09-.05c.04-.03.05-.07.04-.11h.03s.09-.06.09-.06c.02-.03.04-.05.08-.08.05-.06.08-.1.07-.15l.02-.04c.08-.02.12-.06.1-.12v-.06s-.05.02-.07.04c-.02,0-.03,0-.03,0-.03.05-.05.09-.04.11-.11.09-.18.15-.19.17-.02.03-.03.05-.05.08-.02.03-.04.05-.08.08l-.26.32-.02.07.09-.02ZM5.58,42.11c.1-.04.16-.1.19-.17l.02-.04h-.03s-.03.01-.03.01l-.06.04-.1.12-.02.04h.03ZM5.88,41.81s.05-.03.08-.08l-.04-.02-.07.11h.03ZM6.32,42.34l.07-.11c.03-.05.06-.08.08-.08l.14-.13.14-.26v-.03s-.04,0-.04,0c-.13.2-.2.3-.2.3-.04,0-.06.04-.04.11-.06.03-.11.07-.14.1-.02.03-.03.05-.05.08l-.02.07.06-.04ZM5.98,41.69s.07-.03.09-.05c0,0,.03-.05.1-.15.02,0,.03,0,.03,0,0-.02,0-.03,0-.03h-.06s-.15.21-.15.21v.03ZM5.94,41.96s.03-.05.1-.15c.04,0,.06-.02.06-.04.11-.11.18-.2.23-.28,0,0,.02-.03.05-.08.02,0,.05-.03.08-.08l.28-.39s.06-.04.06-.04c0-.02-.03-.04-.08-.05,0-.02-.02-.03-.04-.02l-.02.07-.02.07-.41.55s-.05.07-.1.12c-.05.06-.08.12-.09.18l-.09.05-.06.04-.02.04v.03s.07-.01.07-.01ZM6.84,41.7c.03-.07.05-.12.07-.15h-.03s-.08.09-.08.09c-.02.03-.02.05-.02.07.02,0,.03,0,.03,0h.03ZM6.51,41.09s-.03,0-.03,0c0-.02,0-.03,0-.03l-.07.11s.03,0,.04.02l.07-.11ZM6.56,41.04s.02-.04.02-.04c.02-.03.02-.05.02-.07v-.03s-.08.11-.08.11c.02,0,.03,0,.04.02ZM6.98,41.48s.05-.03.08-.08c.03-.07.04-.13.03-.17l.04.02s.08-.03.12-.06c.03-.05.04-.1.04-.14l-.04-.02c-.07.1-.12.17-.15.2-.07.1-.12.17-.15.2v.06s.04,0,.04,0ZM7.29,41.54l.18-.24v-.03s-.02,0-.04,0t0,0l-.18.24v.03s.04,0,.04,0ZM5.83,40.55l.18-.24-.04-.02h-.03s.03-.01.02-.03l.14-.13s0-.03.02-.04l-.07-.02-.11.09-.11.25-.04.14h.03ZM6.81,40.83s.05-.03.08-.08l-.07-.02-.02.07v.03ZM6.99,40.59c.03-.05.06-.08.08-.08.02-.03.01-.04,0-.03,0-.02-.02-.03-.04-.02,0,0,0,.01,0,.03-.02,0-.05.03-.08.08v.03s.04,0,.04,0ZM7.75,40.92s0-.08.01-.1c0,0-.01,0-.03,0,0,0,0-.01,0-.03l-.04.11.07.02ZM6.37,39.84s-.03.03-.03,0l.07-.11s.01,0,.03,0l-.07.11ZM6.5,41.65s-.03-.03,0-.03c.04,0,.06-.02.06-.04.03-.05.05-.08.05-.08,0-.04.02-.07.08-.08l.02-.04.23-.31.04-.11.35-.5s.04-.06.07-.11c.03-.07.06-.12.1-.15.04-.03.06-.07.07-.11.03-.07.05-.12.07-.15.04-.03.06-.07.07-.11.01-.05.03-.08.04-.11.08-.13.12-.2.12-.22l.04-.11.22-.34.04-.14h-.03c-.06.02-.09.05-.08.09l-.27.55-.35.63c-.11.18-.17.27-.17.27,0,0-.08.13-.24.38-.16.25-.24.38-.24.38l-.18.24c-.05.08-.06.12-.04.14-.03-.04-.07-.02-.12.06v.06s.07-.04.07-.04ZM7.81,40.74h.03c.08-.02.12-.08.1-.16,0-.02,0-.03.02-.04v-.03s-.08-.02-.08-.02c-.01.05-.05.12-.12.22v.03s.04,0,.04,0ZM7.19,40.32c.08-.13.12-.19.12-.19v-.03s-.04,0-.04,0c-.05.06-.09.12-.12.19h-.03s.07.02.07.02ZM8.37,40.78s.03,0,.03,0c0-.02,0-.03,0-.03h-.03s-.1.16-.1.16c0,0,0,.01,0,.03.02,0,.03-.02.02-.04l.07-.11ZM7.55,39.72s.06-.03.05-.08l.07-.11h-.03s0-.02,0-.02l-.02.04h-.03s-.06.07-.07.12c0,.02,0,.04-.02.07.02,0,.03,0,.04.02l.02-.04ZM7.51,40.74l.04-.14c.06-.01.1-.05.1-.12l.07-.11c.11-.11.16-.21.16-.3.05-.08.07-.11.07-.11.04-.03.06-.08.07-.15.03-.07.06-.13.09-.18,0-.02,0-.03,0-.03.02-.03.03-.05.05-.08l.13-.29.11-.38c.03-.05.06-.14.07-.28l.02-.04.02-.04-.06.04s-.02.03-.05.08c-.04.14-.06.22-.08.25l-.21.54h-.03s-.03.06-.1.16l-.21.41c-.12.24-.18.38-.18.4-.02,0-.03.03-.02.07,0,.02,0,.06-.04.11l-.02.07h-.03s-.14.27-.14.27c0,0,0,.01,0,.03.02,0,.03-.02.02-.04l.1-.12ZM7.79,39.3v-.03s-.04,0-.04,0c-.02,0-.05.03-.08.08l.04.06.07-.11ZM8.48,39.64s.03-.02.02-.04l.12-.19-.04-.02-.12.22v.03ZM2.9,42.27c.16-.06.32-.16.46-.3.12-.14.24-.21.35-.21.1-.02.17-.05.21-.08.22-.11.46-.25.73-.42l.33-.3c.23-.16.4-.35.53-.57.06-.12.24-.35.54-.67.02,0,.03-.02.02-.04.03.02.05.02.07.02.02,0,.04,0,.06-.01h.03s-.02.03-.02.03c-.02.09-.05.15-.09.18-.02.03-.02.06-.01.1.03.02.04.02.04.02l.09-.02s0-.03.02-.04l.02-.04-.02.04v.1s0-.04.04-.04l.02-.04c.18-.19.3-.36.38-.51l.07-.15s.02-.05.02-.07c0-.04,0-.08.01-.1.05-.06.11-.13.18-.24.06-.12.12-.22.16-.3.02-.03.03-.05.05-.08.01-.05.01-.09,0-.13.02-.11.06-.2.11-.25l.13-.29.07-.11c.04-.14.09-.27.18-.4.02-.03.02-.06.01-.1l.1-.15.07-.11v-.1s.03-.05.03-.07c0-.02,0-.03,0-.03.04,0,.06-.04.04-.11v-.13c.04-.05.06-.08.08-.08-.03-.06-.03-.1,0-.13v-.03s-.01-.12.07-.25l.02-.07h-.06s-.06.06-.06.06h-.03s0-.02,0-.02l.02-.04s.06-.02.06-.04l.13-.29.06-.04h-.06s-.04-.01-.04-.01l.03-.17s.02-.09.04-.14c0-.07.01-.13.02-.2,0-.04,0-.08.01-.1.04,0,.08,0,.1.01.04,0,.06-.02.06-.04-.02-.17-.02-.32,0-.46.01-.13.02-.25.03-.33.02-.03.02-.15.02-.36l-.07-.18-.08-.67c-.01-.06-.04-.09-.08-.08-.02,0-.03,0-.03,0,0-.02,0-.04.02-.07l.02-.07-.07-.02h-.06s-.37.13-.37.13h-.03s.02-.03.02-.03l.11-.09s0-.03,0-.03c.02,0,.03,0,.03,0h-.03s-.28.07-.28.07l-.28.06-.41.22h-.06s.06-.03.06-.03l.02-.04s-.03-.06-.08-.05c-.02,0-.05,0-.1-.01-.03-.04-.06-.03-.09.02l-.06.04c-.11-.02-.22.01-.31.1l-.23.15-.02.04.04.02h.03s.03,0,.04.02l-.17.1c-.06.01-.1.03-.12.06-.03.07-.07.14-.12.19-.09.19-.17.33-.24.41l-.07.11-.29.19-.02.07h.06s.29-.18.29-.18h.06s-.02.02-.02.02c-.21.13-.35.22-.4.25l-.49.3s-.04.06-.07.11c-.02.03-.05.04-.09.05-.09.09-.13.17-.11.25l-.05.08h-.13s-.04-.05-.05-.09c.01-.05.02-.07.02-.07,0-.04-.03-.06-.08-.05-.15.03-.26.13-.33.3l-.06.04s-.09.05-.14.13c-.03.07-.04.13-.03.17l-.02.07c-.03.05-.05.09-.04.11l-.06.18-.27,1.01-.15.66-.1.58-.2,1.32c-.02.11-.04.36-.07.74v.62c.02.17.03.48.05.94h.03s.02.09.02.09c.04.17.14.23.3.2ZM8.28,40.51s.04-.05.08-.08c.03-.05.03-.11,0-.16l.18-.2c.02-.09.06-.12.11-.09h.06s-.04-.04-.04-.04l-.04-.06c.08-.13.13-.22.13-.29l.05-.08s0,.01,0,.03c0,0,.01,0,.03,0v.03s0-.03,0-.03c.02,0,.03,0,.03,0-.03-.04-.03-.09,0-.16.02-.03.03-.03.03,0,.02,0,.04,0,.06-.01l.09-.18s-.02-.03-.04-.02h-.03s.05-.07.05-.07c.03.02.05.01.06-.01.02-.03.02-.04.02-.04.03-.05.06-.12.08-.21l.02-.07-.06.04h-.03s0-.02,0-.02l.18-.4v-.06s-.08.01-.08.01c-.02.09-.05.15-.09.18l-.33.76v.13s-.21.41-.21.41c-.07.1-.1.15-.1.15,0,.07-.04.12-.1.15l-.03.17-.15.2v.03s.04.02.04.02ZM9.12,39.57c.03-.05.06-.12.08-.21,0,0-.03.05-.1.15v.03s.01.03.01.03ZM8.18,38.83l.05-.08.04-.11v-.03s-.04.02-.03.04l-.07.11-.02.04v.06s.04-.04.04-.04ZM8.04,40.33l.06-.04s.03.04.06-.01l.07-.15s0-.03,0-.03c.02,0,.03,0,.03,0v-.03c-.06-.03-.06-.06-.03-.09,0,0,.02-.01.06-.04.04-.03.03-.06-.02-.09,0,0,.01,0,.04.02.04,0,.05-.04.01-.1h.03s.07-.11.08-.22c0-.02,0-.03.02-.04,0,0,.04-.06.12-.19l.17-.43.18-.4.14-.42v-.06s0-.06.04-.04h.03s0-.09.04-.15c.02-.09.05-.17.08-.25.02-.09.04-.16.05-.21.02-.03.01-.05-.01-.06,0-.02,0-.04.02-.07,0-.02-.02-.03-.04-.02l-.09.05-.05.24-.07.28-.07.15-.1.28s-.03.02-.02.04t0,0s0,.08-.01.1l-.04.14v.13c-.05-.01-.08,0-.09.05-.02.03-.02.05-.02.07-.05.08-.04.13.03.16l-.11.09c-.02.09-.05.16-.08.21-.07.1-.14.27-.22.51l-.07.15c-.09.09-.13.2-.12.35l-.14.13-.02.07.06-.04ZM8.95,38.62h-.03c-.03.06-.06.13-.08.22v.03s.12-.25.12-.25ZM8.4,38.35s-.02-.03-.04-.02c-.03.05-.05.09-.04.11v.03s.08-.11.08-.11ZM8.2,38.03s-.02-.03-.04-.02l-.04.11v.03s.08-.11.08-.11ZM4.63,36.36s-.04-.01-.04-.06c.03-.18.02-.45-.01-.82.02-.09.05-.15.09-.18,0,0,.06-.09.17-.27v-.03s0-.04.01-.07c.02-.03.03-.04.06-.04v.03s-.13.26-.13.26c-.06.14-.08.35-.06.63l-.05.5-.02.04ZM8.24,37.93c.03-.05.05-.09.04-.11,0-.02-.02-.03-.04-.02,0,.02,0,.06-.04.11.02,0,.03,0,.04.02ZM9.34,39.06s0-.03,0-.03c.02,0,.03,0,.03,0l.07-.15s.03-.06.04-.11c.01-.05.05-.08.11-.09v-.03s0-.03.04-.08v-.06s-.05-.02-.05-.02h.06s.02-.05.02-.05c-.03-.02-.03-.03,0-.03.02-.03.03-.04.06-.04v-.03s0-.13,0-.13c.04-.03.06-.08.07-.15,0-.07.02-.11.04-.14v-.03s-.04,0-.04,0l-.02.07-.25.64-.07.28s-.04.02-.06.04c-.02.03-.03.05-.05.08v.06ZM8.3,37.75s.03-.02.02-.04l.08-.21v-.03s-.06.04-.06.04l-.06.18v.06ZM8.4,37.43s.03,0,.03,0c0-.02,0-.03,0-.03l.06-.04.04-.14h-.03s-.06.18-.06.18c-.02,0-.03.02-.02.04ZM8.67,37.64c.07-.17.11-.26.1-.28l.05-.21s0-.03.02-.04c.02-.03.02-.04.02-.04-.03-.04-.02-.11.01-.23v-.03s-.02,0-.04,0c0,0,0,.01,0,.03-.02.03-.04.11-.08.25l-.06.18h-.03s-.03-.12-.03-.12c.02,0,.03,0,.04.02l.02-.07v-.1s.02-.1.02-.1v-.03s-.02,0-.04,0c0,0,0,.01,0,.03l-.05.24c-.03.05-.05.09-.04.11.03.04.04.09.03.16,0,.04.02.07.02.09v.06s-.01.04-.01.04h-.03s.04.03.04.03ZM9.32,37.76l.04-.14-.03-.13c.05-.08.08-.18.1-.32l-.05-.09h-.03s0,.04,0,.04v.06s0,.2,0,.2l-.1.28-.02.07v.03s.04,0,.04,0c0-.02,0-.03,0-.03.02,0,.03,0,.03,0v.06s.04-.04.04-.04ZM9.92,37.66l.04-.11v-.03s-.04,0-.04,0l-.1.15.04.06h.03s.02-.08.02-.08ZM9.28,37.11l.04-.14v-.03s-.04,0-.04,0l-.07.15v.06s.07-.04.07-.04ZM9.33,38.28s.03-.05.05-.08c.01-.05.02-.08.01-.1,0-.04,0-.08.01-.1.02-.03.03-.05.05-.08.01-.05.03-.11.06-.18.02-.09.05-.18.07-.28l.12-.35.16-.62s.01-.04,0-.03c0-.02,0-.03.02-.04v-.06s.05-.18.05-.18l-.04-.02s-.01,0-.03,0c0,0,0,.01,0,.03l-.1.32-.05.24-.06.18s-.03.07-.04.14c0,.04,0,.08-.01.1-.01.05-.03.09-.07.15-.01.05-.02.1-.03.17-.08.24-.13.41-.15.52-.03.05-.05.09-.04.11,0,.04,0,.07-.05.08v.03s.05.06.05.06ZM4.07,33.66s.03-.02.02-.04c.02,0,.05-.03.08-.08.08-.02.14-.04.18-.07.02,0,.03-.02.02-.04,0-.02,0-.03.02-.04,0,0,.02-.03.05-.08v-.03s-.08-.02-.08-.02l-.11.09s-.02.01-.06.04c-.02.03-.01.05.01.06,0,0,0,.01,0,.03,0-.02-.02-.03-.04-.02v-.03s-.04.02-.03.04l-.1.12s0,.03-.02.04c0,0,0,.01,0,.03,0,0,.01,0,.03,0ZM8.83,36.13s.01-.04,0-.03c0-.02-.02-.03-.04-.02-.02,0-.03.02-.02.04l-.05.21.04.02.08-.21ZM4.57,33.26s.03-.02.02-.04c-.03-.02-.06-.02-.1-.01,0,0-.01,0-.03,0l.04.02s.03,0,.04.02l-.02.04.06-.04ZM9.15,36.84s.03-.05.05-.08c.02-.03.02-.06.01-.1,0-.04,0-.08.01-.1.01-.05.02-.08.01-.1.03-.07.06-.11.1-.12.02-.03.01-.04,0-.03,0-.02,0-.04-.01-.06.01-.13.04-.23.07-.28,0-.04,0-.08.01-.1.01-.05.03-.08.04-.11-.05-.01-.06-.02-.04-.02.02,0,.03-.02.02-.04,0-.04-.02-.06-.04-.06l-.06.04-.02.07s-.02.07-.07.15c-.03.07-.05.17-.06.31-.02.09-.04.23-.04.4l-.02.2v.03s.04,0,.04,0ZM8.91,36.01s0-.09.04-.14c.05-.08.05-.13,0-.16,0,0,0-.02-.01-.06l-.04-.06h-.03s.02.1.02.1v.03s.02.06.02.06l-.04.14s-.01,0-.03,0c0,0,0,.01,0,.03l-.06.04s.03.02.08.05l.06-.04ZM9.44,37.11s.02-.03.05-.08c.02-.03.03-.06.04-.11,0-.07,0-.13,0-.19v-.03c.06-.1.08-.23.04-.37.06-.01.08-.06.07-.15,0-.02,0-.05.01-.1,0-.07,0-.11-.03-.13v-.1c.09-.13.09-.24,0-.33v-.03c.06-.01.06-.04.01-.07v-.06s.02-.02.01-.04h-.03s-.06.05-.06.05c-.04.23-.04.39,0,.49,0,.04,0,.11-.02.2-.07.1-.06.19.02.26-.06.01-.08.07-.06.18l-.06.18h-.03s0-.02,0-.02l.03-.3-.02-.09-.05.08s0,.06-.02.07l-.07-.02.04.06c.07,0,.08.04.05.09-.02.09-.03.15-.03.17-.02,0-.03.02-.02.04.03.02.04.02.04.02.06-.03.08-.03.07.02,0,.02,0,.03-.02.04,0,.02,0,.05-.01.1,0,.04,0,.08-.04.11,0,.02.03.05.08.08ZM4.86,33.06v-.03s-.04,0-.04,0c-.04,0-.07.03-.09.05h-.03s.03.06.08.06l.08-.08ZM8.29,35.3s-.01,0-.03,0t0,0l-.06.04.07.02.02-.07ZM8.17,34.44v-.06c.02-.05.04-.12.04-.21,0-.09,0-.15,0-.19,0-.02,0-.03,0-.03.02,0,.03,0,.03,0v.03s.06.38.06.38l-.02.07s-.02.03-.05.08l-.04-.06ZM10.43,35.62l.04-.11-.04-.06h-.03s-.04.15-.04.15v.06s.07-.04.07-.04ZM9.62,34.91s0-.08.01-.1l-.04-.02h-.03s-.01,0-.03.01c0,0,.01,0,.04.02,0,.04.03.07.05.09ZM9.54,34.73s.01.05,0,.03c.02-.03.02-.04.02-.04.05.01.07,0,.06-.01.02-.03.02-.04.02-.04,0-.02-.02-.03-.04-.02l-.08.08ZM10.05,35.11c.04-.12.05-.22.03-.3l-.04-.06-.02.07v.29s.03,0,.03,0ZM9.56,34.5s.05-.03.08-.08c-.04,0-.06,0-.07-.02-.04,0-.06.03-.05.08l.04.02ZM10.03,34.72s0-.03,0-.03c.02,0,.03,0,.03,0-.01-.06,0-.12.03-.17l-.04-.02h-.03s0,.17,0,.17c0,0,0,.02.01.06ZM7.87,33.06c-.05-.03-.08-.05-.08-.05v-.06s.02,0,.02,0l.08.08-.02.04ZM10.08,34.19l-.04-.06v.1s0,.06,0,.06l.04-.11ZM9.94,33.86s-.02-.03-.04-.02v.03s0,.12.02.23v-.23ZM10.41,33.89s.01-.05-.01-.06c0-.04-.02-.07-.02-.09h-.03c.01.07.01.12,0,.17l.04.06.02-.07ZM6.43,31.28h.03s.04.02.04.02c.02-.03.02-.05.02-.07l.02-.04s0-.03,0-.03c.02,0,.03,0,.03,0h-.03c-.08.03-.14.05-.18.08,0,0-.01,0-.03,0,0,0,0,.01,0,.03l.04.02h.06ZM9.93,33.66c-.03-.12-.01-.22.04-.27,0,0,0-.02-.01-.06v-.03s-.02.07-.02.07h-.03s-.07-.31-.07-.31v-.06s.02-.02.01-.04c0,0-.03-.02-.08-.05l-.02.07v.06s.12.34.12.34v.3s.01.06.01.06l.05-.08ZM9.4,32.99v-.03s-.03-.12-.03-.12v-.03s-.07.01-.07.01v.03s.04.16.04.16l.04.06.02-.07ZM7.37,31.5l-.11-.04h-.06s0,.04,0,.04c0,.04.02.06.04.06l.13-.03v-.03ZM6.89,31.28s.07-.03.09-.05v-.03s-.04,0-.04,0l-.06.04s-.01,0-.03,0c0,0,0,.01,0,.03,0,0,0,.01,0,.03,0,0,.01,0,.03,0v-.03ZM6.83,31.13s.04-.02.06-.04c.04-.03.07-.04.09-.02l.05-.08h-.06c-.06.03-.11.05-.15.08-.08.02-.14.04-.18.07v.03s.19-.04.19-.04ZM9.31,32.75s.03,0,.03,0c0-.02,0-.03,0-.03v-.03s-.04,0-.04,0c0-.02,0-.03,0-.03v-.1s-.03-.06-.03-.06c0,.02,0,.03-.02.04v.13c0,.06.04.09.08.08ZM7.48,31.25v-.03s-.05,0-.07.01c0-.02,0-.04-.01-.06h-.03c0,.07-.06.12-.17.14v.06s.14-.03.14-.03c0,.02,0,.03,0,.03.02,0,.03,0,.03,0l.1-.12ZM7.46,31.48c.06-.01.09-.04.08-.08,0-.02,0-.04.02-.07.02-.03.03-.04.06-.04l.26-.02h.03s-.01-.07-.01-.07h-.06s-.06.02-.07,0c-.05-.01-.09-.01-.13,0-.03-.02-.05-.01-.06.01l-.07.11s.02.06-.02.07c0,0-.02.03-.05.08l.04.02ZM7.91,31.42c.08-.02.12-.06.1-.12v-.03s-.07.01-.07.01c-.01.05-.05.08-.11.09-.05-.01-.07,0-.06.01h-.03s-.07-.01-.07-.01h-.06c.05.05.08.06.08.06l.23-.02ZM9.53,32.11l-.08-.08v.06s.06.06.06.06l.02-.04ZM14.46,45.64c-.05-.03-.14-.06-.28-.07-.01.05-.04.05-.09.02-.16,0-.25-.05-.29-.13l-.13-.17-.09-.11v-.06s-.04-.07-.07-.09h-.03s-.04-.06-.1-.14c0-.02-.02-.05-.05-.09,0-.02,0-.06,0-.13.02-.03,0-.09-.07-.18-.03-.04-.06-.03-.09.02v.03s-.03,0-.03-.02c-.03-.12-.06-.22-.09-.27,0-.02-.03-.05-.08-.08v-.06s.02.02.02.02h.03c-.01-.07-.03-.1-.05-.09-.02,0-.03,0-.04-.02-.01-.06-.01-.11,0-.13,0-.02-.01-.05-.02-.09v-.03s-.03.04-.03.04v.06s-.02,0-.02,0c-.03-.02-.04-.06-.06-.12-.03-.04-.04-.07-.02-.09,0-.02,0-.04-.01-.06h.03c.03-.06.05-.09.04-.11,0-.02-.03-.05-.08-.08-.03-.04-.05-.1-.07-.18-.02-.08-.02-.18,0-.29,0-.11,0-.18-.02-.23.01-.05.02-.1.03-.17s.02-.14.05-.21c.01-.13.02-.21.01-.23v-.03s-.02,0-.04,0c0,0,0,.01,0,.03l-.05.24c-.02.09-.03.16-.02.2l-.06.04v-.06s-.02-.11,0-.2c-.01-.06,0-.14.01-.23,0-.09,0-.17.01-.23,0-.07.01-.13.02-.2l.03-.3s.02,0,0,0c0-.02,0-.03,0-.03v-.06s-.02-.11,0-.2v-.03s-.04,0-.04,0l-.02.07-.02.04v-.03s-.02,0-.04,0c0,0,0-.01,0-.03v.03s-.05.21-.05.21l-.02.04v-.03c-.02-.08-.03-.15-.02-.19-.01-.06-.01-.11,0-.13.01-.05.02-.09.04-.14l-.04-.19h-.03s-.03.02-.02.04l-.06.04s-.01,0-.03,0c0-.02,0-.03.02-.04-.02-.08,0-.14.03-.17v-.03c0-.09,0-.19.03-.3.02-.11.03-.19.05-.24.02-.09.03-.16.02-.2.02-.03.01-.04,0-.03,0-.02,0-.04-.01-.06-.04,0-.06.02-.06.04,0,0-.02.03-.05.08l-.02-.09.04-.14v-.03s-.04,0-.04,0c0,.04,0,.09-.04.14v.03s-.01-.03-.03-.02v-.13s0-.03,0-.03c-.02,0-.03.02-.02.04-.03.05-.04.11-.03.17-.02,0-.03.02-.02.04h.06s0,0,0,.02c0,0,.01,0,.03,0-.02,0-.03.02-.02.04-.07,0-.09.03-.07.11l-.16.46v-.03s.03-.27.03-.27c.04-.21.07-.41.1-.61l.09-.48.02-.07s-.06.02-.06.04l-.05.21-.02.07s0-.06.02-.07l.14-.72c.06-.21.13-.54.21-1l.12-.52c.03-.16.07-.33.12-.52.04-.21.07-.42.09-.64,0-.13,0-.24.03-.33.02-.09.04-.17.05-.24.06-.32.1-.56.11-.71l.11-.84.1-.61c.03-.27.04-.47.03-.6l.06-.18c.06-.34.09-.63.1-.87,0-.09.03-.22.07-.41l.03-1.09.12-.52.03-.3.05-.21.05-.08c-.01-.06-.01-.16,0-.3l.13-.32s.02-.06.01-.1c.03-.05.06-.08.08-.08.06-.01.13-.05.21-.11v-.03c0-.07,0-.15-.03-.26-.01-.06.03-.13.12-.19.04,0,.07-.03.09-.05s.03-.05.05-.08c0-.02,0-.06.04-.11,0-.02,0-.03.02-.04l-.02-.09.06-.04-.02.04.04.06s.03,0,.03,0c0-.02,0-.03,0-.03.04,0,.06,0,.07.02h.03s.03-.01.03-.01v.03s-.05.18-.05.18l.02.09.02-.07s.04-.06.14-.13c.02,0,.06-.01.12-.03.08-.04.13-.09.16-.17l.02-.04.04.06s.03.07.05.09c.03-.05.05-.08.05-.08.02-.03.07-.15.15-.36.07-.06.12-.11.13-.16,0,0,.01,0,.03,0,.02,0,.03,0,.04.02.03.06.09.06.16,0,0-.02,0-.03.02-.04l-.02.07s0,.04-.02.07c-.02.03-.01.05.01.06.03.02.07.02.13,0,.08-.02.11-.07.07-.15,0-.04,0-.07.05-.08.06-.01.11-.05.14-.1.04-.03.09-.05.15-.07.06-.01.12-.01.16,0,0,0,.03.02.08.05.03.04.03.09,0,.16-.01.05-.02.08-.01.1,0,.04.02.06.04.06v.03s-.1.12-.1.12v.06c.14.06.22.21.27.44l.05.25c.04.17.04.41.02.72.01.15.05.37.11.66l.04.19c.05.25.14.51.27.79.07.14.17.37.28.69.04.08.06.16.05.25.02.08.05.16.09.24.02.1.08.26.16.46.08.29.22.64.39,1.06l.31.82.24.64c.11.28.18.51.21.67.11.32.19.57.23.74,0,.02.02.03.04.02.03.12.08.29.17.49l.1.14c.06.05.13.21.23.47,0,.04.02.1.04.19.03.06.04.12,0,.19l.04.06.06-.04.07-.41.12-.52.11-.38.07-.28.14-.39.09-.35.04-.27s.04-.17.08-.38l.15-.69c0-.07.02-.12.03-.17,0-.07.02-.12.03-.17l.06-.31.16-.79.04-.4.15-.69.13-.62.13-.75.22-.93c.02-.11.04-.22.06-.31.04-.1.07-.18.08-.25.05-.16.11-.41.17-.72l.15-.69.07-.11v.1s-.08.44-.08.44l-.02.07c-.05.06-.08.17-.09.35,0,.02,0,.08-.03.17,0,.09-.03.22-.07.41-.02.09-.05.16-.08.21,0,0,0,.01,0,.03,0,0,.01,0,.03,0h.03s.01-.24.01-.24l.03.13.02.09s-.02.05-.02.07c.03.02.06,0,.09-.02.04-.03.06-.01.08.05-.03-.02-.05-.01-.06.01s-.02.04-.02.04v.06s.05.02.05.02c.05-.08.06-.12.04-.14.07-.06.09-.13.05-.21,0,0-.01,0-.04-.02,0-.04,0-.07.05-.08-.01-.06,0-.1.04-.11.02,0,.03-.03.02-.07-.05-.03-.04-.06.02-.07v-.03s-.04-.02-.04-.02c.02-.03.02-.05.02-.07l.05-.37.05-.21s.04-.11.08-.25l.02-.07h.1s.03,0,.03,0c.02-.03.01-.05-.01-.06h-.03s-.09.06-.09.06l.03-.17.06-.04h.03s.06.02.09-.03l.06-.18s0-.06.02-.07l.02-.07v.06s-.04.37-.04.37l-.02.07c-.03.05-.04.08-.01.1-.02.03-.02.06-.01.1.03.02.03.04.01.06v.03s0,0-.02,0c0,0,0-.01,0-.03v-.03s-.01-.03-.01-.03v.03s-.03.14-.03.14c-.03.05-.02.08.05.09v.06c0,.09-.01.17,0,.23,0,0,0,.02-.02.07,0,.02.03.03.07.02l.02.09s-.03.02-.02.04h.06s.06-.19.06-.19c.04-.1.09-.26.12-.49l.04-.27s0-.03,0-.03c.02,0,.03,0,.03,0v.03c-.04.16-.07.32-.05.47v.03s.04-.02.03-.04l.06-.34s.04-.15.09-.32c0-.02,0-.03,0-.03.02-.03.01-.05-.01-.06,0-.02,0-.03.02-.04.02-.03.02-.06.01-.1l.04.02s-.02.05-.02.07c.03.02.03.04.01.06-.02.03-.01.1.02.23l.06-.04.05-.24c.03-.05.07-.08.11-.09l.06-.04.02-.07-.02.04-.06.04s0-.06.02-.07c0-.02,0-.06.04-.11h.03s.03-.18.03-.18c.02,0,.03,0,.03,0,0-.02,0-.03,0-.03.08-.02.11-.09.08-.21,0-.02,0-.03.02-.04.04-.03.07-.04.09-.02.09.02.16.02.19,0h.06s0,.02-.02.02l-.19.34-.08.38s-.03.02-.02.04c.02,0,.03-.02.02-.04.04-.03.07-.09.09-.18l.06-.18c0-.09.06-.18.17-.27.04-.03.07-.09.09-.18l.07-.11h.06s.02.08.02.08l-.02.04h.03s.06-.04.05-.08c-.03-.02-.03-.03,0-.03.02-.03.03-.04.06-.04.06-.01.1-.08.12-.19,0,0,.07-.1.2-.3v.03s-.07.25-.07.25c0,.07,0,.13.04.19.05.03.09.05.11.04.06-.01.08,0,.04.06l-.04.11c-.13.2-.22.44-.27.71-.09.39-.14.77-.14,1.14-.02.11-.04.24-.05.37,0,.13,0,.25-.02.36-.02.29-.07.62-.15.98,0,.16-.05.39-.11.71,0,.07-.02.19-.05.37-.01.15-.04.3-.1.45v.16s-.11.84-.11.84l-.06.63c-.04.34-.07.55-.09.64,0,.13-.02.28-.07.44-.03.25-.1.51-.19.79,0,.22,0,.37-.03.47l-.02.07-.06.34-.06.8-.06.63c0,.07-.02.12-.03.17-.02.03-.03.05-.05.08,0,.04,0,.08-.01.1,0,.02,0,.08-.03.17-.07.37-.14.62-.19.76l-.05.21s0,.06-.02.07l-.17.72c-.1.24-.14.48-.11.71l-.06.31-.07.57c-.04.12-.07.24-.08.38,0,.11,0,.21-.03.3-.03.07-.02.19.01.36.02.08.07.13.16.13.07,0,.11.03.11.07.03.04.04.08.03.12l-.03.3.02.26c.02.08,0,.14-.06.18l-.22.18-.06.04c-.02.09-.09.16-.18.2-.08.04-.13.06-.15.07l-.2.14s-.1.03-.18.07c-.07.06-.15.09-.21.08l-.55.05-.21-.05c-.36-.05-.62-.1-.79-.16-.07,0-.13-.03-.18-.06-.03-.04-.07-.06-.11-.07-.18-.13-.38-.33-.59-.59-.17-.2-.37-.5-.59-.89l-.41-.66-.21-.51c-.07-.12-.11-.23-.14-.33-.08-.16-.18-.42-.3-.79-.05-.12-.11-.29-.18-.52-.07-.22-.13-.43-.17-.62-.04-.1-.07-.19-.09-.27,0-.11-.02-.21-.07-.31l-.1-.47c-.09-.2-.14-.35-.16-.46l-.24-.8c-.04-.17-.11-.39-.21-.67-.03-.15-.1-.36-.21-.64-.01-.06-.05-.11-.1-.14l-.04.14c-.05.18-.07.32-.07.41.02.08.02.18,0,.3-.02.09-.04.16-.05.21l-.07.41c-.04.14-.07.28-.11.42-.04.14-.06.26-.08.38-.07.39-.12.62-.15.69,0,.07-.04.17-.1.32.01.06.01.11,0,.13,0,.04-.02.17-.08.38,0,.04-.02.17-.08.38l-.2.89-.19.76-.14.85-.08.54c-.04.21-.07.33-.08.38l-.04.27c-.03.07-.05.17-.06.31,0,.09,0,.19,0,.3,0,.09-.02.18-.04.27-.03.38,0,.71.05,1l.1.47.09.41c.06.18.21.4.44.66,0,.02.02.03.04.02.03.02.04.03.04.06.03.02.04.05.05.09-.04,0-.06,0-.07-.02-.03-.02-.05,0-.09.05-.03.07-.08.08-.16.03l-.18-.09ZM12.93,44.77s-.03,0-.04-.02l-.06-.28.04.06.05.22s.04.02.04.02c-.02,0-.03,0-.03,0ZM13.06,44.74s-.03,0-.04-.02l-.08-.08v-.1s.04,0,.04,0c.03.04.05.1.07.18v.03ZM12.93,44.44s-.06-.03-.09.02v-.13s0-.03.03-.04c0,.02,0,.03,0,.03l.09.11s0,.03-.02.04v-.03ZM12.41,43.73v-.23s0-.03,0-.03v.03c.03.1.03.18.02.23h-.03ZM13.04,44.06s.03-.02.02-.04c.02-.03.02-.07,0-.13v-.03s-.04.02-.03.04c-.02.03-.02.07,0,.13v.03ZM12.89,41.73l-.08-.05-.03.17h.03s.07-.12.07-.12ZM11.88,40.54c.04-.14.06-.22.08-.25v-.03s0,.03,0,.03l-.04.27s-.03.02-.02.04v-.06ZM12.8,40.86c.06-.12.07-.28.03-.46h-.03c-.01.05-.02.1-.04.15-.02.03-.02.07,0,.13.02.08.02.15,0,.19v.03s.03-.04.03-.04ZM13.69,39.52s.03-.02.02-.04l.04-.14v-.03s-.04,0-.04,0c0,.02,0,.08-.03.17v.03ZM14.16,37.62h-.03s-.06.18-.06.18v.03s.04,0,.04,0l.05-.21ZM13.25,37.07c.02-.09.03-.15.03-.17v-.03s-.06.21-.06.21h.03ZM14.19,37.45s.03-.02.02-.04l.02-.04c.06-.32.12-.56.17-.72,0-.02,0-.06,0-.13,0-.07.02-.11.04-.14l.08-.54.09-.35v-.03s-.04.02-.03.04l-.08.25.02.09s-.02.03-.05.08c-.11.5-.18.88-.21,1.13l-.08.38v.03ZM18.24,38.6l-.05-.09-.02.07.05.09.02-.07ZM18.16,37.5l-.08-.08s-.02-.03-.04-.02v.03s.07.12.07.12c.02,0,.03,0,.04.02l.02-.07ZM14.69,35.08l.02-.2v-.03s-.06.21-.06.21v.03s.04,0,.04,0ZM17.98,37.28l.02-.07v-.03s-.02,0-.04,0c0,0,0,.01,0,.03l-.02.04c.05.03.08.05.08.05l-.04-.02ZM18.17,36.19l-.02-.09h-.03s-.03.01-.03.01v.13s.03,0,.03,0l.06-.04ZM17.49,35.62l-.03-.13-.04-.02v.03s-.01.06,0,.1v.03s.04,0,.04,0h.03ZM16.8,34.56l-.02-.09v-.03s-.04,0-.04,0c.01.06.01.11,0,.13,0,.02.03.03.07.02v-.03ZM17.45,34.25l.02-.04v-.03s-.07.01-.07.01c0,0-.01,0-.03,0,0,0,0,.01,0,.03.03.02.04.05.05.09l.02-.07ZM17.3,33.83s0-.03,0-.03c.02,0,.03,0,.03,0l.02-.07s-.04-.01-.04-.06h-.03s.04.06.04.06c0,.02,0,.03-.02.04v.06ZM21.76,34.79l-.07.11.04.02.04-.14ZM15.68,30.31s0-.03,0-.03c.02,0,.03,0,.03,0l-.05-.09-.02.07.04.06ZM21.6,34.33c0-.07.04-.12.1-.15l-.04-.02h-.03s-.07.12-.07.12c0,0,0,.01,0,.03,0,0-.01,0-.03,0l.07.02ZM21.78,34.26c.08-.02.11-.07.07-.15v-.03s-.05-.06-.05-.06l-.02.07s.02.05-.01.1l-.02.07h.03ZM21.74,33.65l-.04-.02-.07.11.08.05.04-.14ZM21.73,33.16s.03-.02.02-.04c.08-.02.12-.06.1-.12,0-.02-.02-.03-.04-.02l-.02.04s0,.06-.06.04l-.02.07v.03ZM22.12,32.52l.02-.07v-.06s-.08-.02-.08-.02v.03s.04.04.02.06l-.02.07h.06ZM21.97,32.15l.04-.27h-.06s0,.04,0,.04c.02,0,.04.01.04.06-.03.05-.05.09-.04.11l.02.09v-.03ZM22.16,32.08s.03-.02.02-.04l.04-.14v-.03s-.04,0-.04,0l-.07.15.04.06ZM22.16,31.82s.05-.03.08-.08c0,0-.01,0-.03,0t0,0s-.06.03-.05.08ZM22.29,31.66v-.06s-.07.04-.07.04h-.03s0,.04-.02.04l.07.02.06-.04ZM22.24,31.41v.03s.07-.02.06-.04c0-.02-.03-.05-.08-.08l-.04.14.06-.04ZM22.29,31.33s0-.03,0-.03c.02,0,.03,0,.03,0v-.03s-.01-.02-.02-.06h-.06s.04.07.04.07v.06ZM22.15,31.17v-.13s0-.03,0-.03h-.03s0,.14,0,.14v.03s.04,0,.04,0ZM22.34,31.12s0-.04-.01-.06c.01-.05.03-.09.07-.15l-.08-.08h-.03s.02.1.02.1v.03s-.01.06,0,.1c0,.02,0,.04-.02.07v.03s.06-.04.06-.04ZM22.39,30.75s-.03-.04-.01-.06c.04-.03.05-.06.05-.08v-.06s-.07.04-.07.04v.1s-.06.08-.06.08l.09-.02ZM22.48,30.24s0-.03.02-.04h-.06s-.01.02-.03.02c0,0,0,.01,0,.03l.04.06.02-.07ZM22.49,29.85c.03-.05.04-.1.04-.14l-.07.11s.02.03.04.02ZM22.61,29.79s.06-.02.06-.04c0-.02-.02-.03-.04-.02l-.06.04s0,.03,0,.03c.02,0,.03,0,.03,0ZM22.74,29.2s0-.08.01-.1h-.03s-.01.11-.01.11v.03s.03-.04.03-.04ZM22.79,28.21s.02-.03.05-.08l.05-.37v-.06s-.02-.03-.02-.03c-.02.03-.05.04-.09.05l-.02.04.08.05s0,.03-.02.04c-.02,0-.03.02-.02.04.02.1.02.18-.01.23l.02.09ZM22.54,27.25c.05-.08.07-.11.07-.11l-.07-.02s0,.06-.04.11l.04.02ZM22.61,26.97s-.02-.03-.04-.02l-.02.07.04.06v-.1ZM22.67,26.79l-.07-.02-.02.04s0,.01,0,.03c0,0,.01,0,.03,0l.06-.04ZM23.36,26.02l.07-.11v.13s-.03.04-.03.04l-.04-.06ZM23.97,26.28s0-.06.04-.11l-.04-.02s-.06.03-.05.08l.04.06ZM23.43,25.91c-.01-.06-.04-.08-.08-.05,0-.02,0-.06.04-.11h.03s.01-.04.06-.05c0,.04,0,.08-.01.1,0,.02,0,.06-.04.11ZM23.44,25.35l.04-.14.04.02-.07.15v-.03ZM36.59,42.83s-.03,0-.04-.02c-.03-.02-.05-.07-.07-.15l-.14-.2c-.06-.1-.18-.16-.34-.19l-.07-.02c-.09,0-.14-.06-.17-.16l-.13-.3c-.04-.08-.06-.17-.06-.28.01-.05,0-.12-.02-.23-.04-.19-.04-.35,0-.49l.03-.33s-.01-.06-.03-.13c0-.04-.03-.08-.06-.12l.02-.04c.03-.05.04-.11.03-.17v-.06s-.02-.03-.02-.03c-.02,0-.03.02-.02.04l-.04.11-.04.27s-.01,0-.03,0c0,.02,0,.02-.03,0l-.02.04c0,.18-.02.31-.04.4,0,.04,0,.08-.01.1l-.02-.09s-.02-.09-.03-.16c0-.07.02-.15.05-.24.02-.03.02-.06.01-.1l-.03-.13v-.49s-.01-.33-.01-.33l-.04-.06s0,.03-.02.04c0,.13,0,.31-.05.53-.04.23-.06.48-.06.77l-.04.43v.03s-.04-.06-.04-.06c.01-.13.01-.23,0-.3.01-.13.01-.24,0-.33.02-.03.01-.05-.01-.06-.05-.01-.08-.02-.1-.01-.02,0-.03,0-.04-.02v-.26s-.03-.19-.03-.19c0-.02-.02-.03-.04-.02l-.02.04-.02.07-.02.04v-.06s.02-.14.02-.14c0-.04,0-.11.02-.2,0-.09-.01-.16-.05-.22-.03-.02-.03-.05-.02-.09,0-.02,0-.03,0-.03l-.04-.06-.06.04-.09.48h-.03s-.04,0-.04-.05c.02-.03.02-.08,0-.16v-.16s.02-.2.02-.2l.02-.07c0-.11,0-.31.03-.6v-.03s-.04.02-.03.04l-.09.18-.02.07s-.03.02-.02.04c0-.04-.01-.06-.01-.06.01-.13.04-.24.06-.31l.04-.27.06-.31v-.13s0-.03,0-.03c-.02,0-.03.02-.02.04h-.03c0,.07-.05.17-.13.3l-.06.18-.04.14-.02.07-.15.52v.03s0-.06,0-.06l.19-.93.16-.62s0-.11.02-.2v-.03s-.04.02-.03.04c-.05.25-.1.4-.13.45,0,.02,0,.03-.02.04v-.03s.01-.07.01-.07v-.06s-.04.04-.04.04h-.03s0-.16,0-.16c.02-.03.03-.05.05-.08.01-.05.02-.1.03-.17v-.23s.04-.33.04-.33c.02-.09.03-.16.02-.2l.04-.4s.02-.09.04-.14c0-.07.01-.13.02-.2l.08-.25v-.03c-.01-.13.02-.33.09-.61,0-.09.03-.2.09-.35.05-.27.07-.42.07-.44l.07-.28c.03-.07,0-.15-.09-.24l-.11-.21-.03-.13c-.09-.09-.12-.16-.11-.21v-.03s-.23-.28-.23-.28l-.13-.17-.06-.12c-.06-.1-.1-.21-.11-.34,0-.2.03-.35.1-.45l.2-.14c.18-.06.36-.17.52-.31.09-.09.23-.19.42-.32l.02-.04c.08-.02.13-.09.15-.23l.09-.35.05-.37c.08-.32.13-.52.13-.59.02-.09.03-.16.02-.2l.05-.24s.04-.17.08-.38v-.4s.11-.45.11-.45c.02-.22.05-.4.11-.55l.13-1.04c.04-.23.06-.39.05-.5l.07-.28.02-.2-.14.13-.31.36-.02.04c.01.06-.02.1-.1.12-.06.01-.11.04-.15.07-.13.03-.19.08-.19.17-.01.05-.04.08-.07.11-.02,0-.05,0-.1-.01-.08-.05-.15-.04-.23.02l-.09.05s-.08,0-.1-.01c-.05-.01-.09-.03-.15-.07-.03-.06-.06-.12-.07-.18,0-.09-.02-.23-.06-.41.01-.05,0-.12-.02-.23l-.07-.15v-.06c.04-.27.08-.44.1-.52l.06-.18c.07-.08.09-.18.06-.31-.02-.08,0-.16.05-.24.05-.08.05-.14,0-.19-.03-.06-.03-.1,0-.13.18-.17.32-.29.41-.35.05-.06.08-.1.07-.15l-.04-.06h-.03s.02-.03.02-.03l.23-.15.45-.33s.07-.03.09-.05c.12-.05.3-.14.53-.28l.29-.19.29-.19s.11-.06.21-.08l.25-.05s.12-.01.23-.02c.13,0,.24,0,.33.03l.27.04.15.07.07.02c.09,0,.2-.03.34-.11l.25-.05s.05-.01.09-.02c.04,0,.08-.04.11-.09h.03s.3-.14.3-.14h.16c.33-.08.6-.11.8-.11.09,0,.22-.01.38-.05.13.01.23.01.29,0,.07,0,.15,0,.26-.02.13.01.22.02.26,0,.09.02.18.03.26,0,.09.02.15.03.17.03.37.09.59.16.66.18.43.17.74.32.92.46.28.18.52.37.71.57.05.03.14.13.26.3l.18.22c.05.03.08.08.1.14.03.06.06.11.07.15.03.15.06.25.1.31.03.02.04.06.06.12l.13.59.13.59c.03.15.03.35,0,.62-.05.18-.09.33-.14.42-.11.29-.21.5-.28.65l-.28.39-.13.29c-.07.08-.13.17-.17.27l-.39.61-.32.46-.35.5s-.06.09-.17.27c-.11.11-.2.22-.29.33-.09.09-.16.16-.22.21l-.35.34-.61.49-.54.38-.56.42-.17.1-.09.05c-.36.25-.57.4-.63.43l-.66.44-.43.26-.49.3c-.08.04-.19.12-.34.24-.02,0-.06.04-.1.12-.04.23-.08.4-.12.52l-.04.14-.13.45-.16.62-.06.18-.07.41-.11.38-.04.27-.04.27c-.03.16-.06.31-.1.45-.02.11-.04.22-.06.31l-.05.24-.04.14-.16.76c-.05.16-.08.33-.09.51-.07.56-.12.92-.13,1.08l-.04.7c0,.22.02.39.05.51,0,.13.04.33.1.6l.07.34c.03.15.05.26.04.35.02.08.02.21.02.39v.03ZM34.96,41.84c-.05-.03-.08-.08-.1-.14v-.03s.02-.02.02-.04l.04.02s.03.07.05.09c-.02,0-.03.02-.02.04l.02.09v-.03ZM35.06,41.82s0-.01,0-.03c0,0-.01,0-.03,0l.02-.07.04.02-.02.07ZM35.95,42.18l-.04-.06-.02.07.07.02v-.03ZM35.3,41.27v-.06s0-.13,0-.13l.04.02s-.01.1,0,.16c0,0-.01,0-.03,0,0,0,0,.01,0,.03v-.03ZM35.04,40.22h-.06s-.02.08-.02.08l.07.02v-.1ZM36.42,28.81l-.04-.06-.04.11s.03,0,.04.02l.05-.08ZM38.69,28.55c-.01-.06,0-.14.01-.23v-.13s0-.03,0-.03h.03s.04.05.04.05c-.01.05-.02.1-.03.17-.01.05-.02.1-.03.17,0,0-.01,0-.03,0,0,0,0,.01,0,.03v-.03ZM39.01,26.87c.06-.14.09-.25.1-.32l.05-.21c.03-.36.05-.57.06-.64,0-.04,0-.07.05-.08.02,0,.03,0,.04.02.03.02.05.02.07.02l-.04.27c-.05.18-.07.33-.07.44-.02,0-.03.02-.02.04-.05.06-.1.13-.15.23-.02.09-.04.16-.05.21,0,.02,0,.06-.04.11v-.1ZM38.72,28.87l.4-.28.56-.42s.13-.09.29-.19l.44-.39c.06-.03.14-.11.25-.22l.22-.18.38-.38.45-.49c.18-.17.3-.31.37-.41l.35-.5.1-.15.13-.29.17-.43c.07-.19.09-.37.08-.54,0-.09-.02-.23-.06-.41v-.06c-.03-.08-.09-.16-.19-.22-.23-.06-.36-.1-.38-.11-.04,0-.16-.03-.35-.12l-.4-.04-.36-.02h-.03s-.07-.03-.15-.06l-.09.02s-.03,0-.04-.02h.03s.03-.01.03-.01c0-.02-.02-.03-.04-.02,0-.02-.03-.03-.07-.02v-.03s.02,0,.02,0v-.03s-.05,0-.07.01c-.03-.02-.05-.01-.06.01l-.09.02c-.08.02-.17.02-.26,0-.09-.02-.16-.03-.2-.02-.09,0-.15.03-.17.1l-.14.39-.18.66-.06.31c-.07.17-.12.27-.13.29-.1.06-.16.17-.2.3l-.17.72-.12.65-.15.69-.03.33-.1.45c-.03.05-.03.09,0,.13v.03s-.05.18-.05.18c-.05.16-.1.43-.16.79-.02.03,0,.06.02.09,0,0,0,.01,0,.03.02,0,.04-.02.06-.04l.18-.07ZM53.54,40.74c-.02-.1-.03-.18-.02-.23.01-.05,0-.1-.03-.16-.03-.06-.05-.11-.03-.16.01-.05,0-.1-.03-.16,0-.04,0-.09,0-.13l-.11-.5s-.02-.05-.05-.09c-.03-.02-.04-.03-.04-.06-.03-.02-.04-.06-.06-.12-.02-.08-.04-.14-.07-.18v-.06s-.02-.04-.03-.06c.02-.03.02-.06.01-.1v-.06s.04.12.04.12v.1s0,.03,0,.03h.03c0-.18,0-.32-.03-.43v-.03s-.03-.05-.06-.09c0-.04,0-.06.02-.07.03-.05.03-.11,0-.16-.03-.04-.05-.08-.06-.12.02,0,.02-.01,0-.03,0-.02,0-.03,0-.03.05-.16.03-.26-.06-.28-.08-.05-.11-.1-.1-.14.03-.05.05-.08.05-.08l-.04-.48c0-.2,0-.45-.03-.75l-.03-.42s0-.01,0-.03c0,0-.01,0-.03,0v.03c-.06.1-.09.15-.09.15v-.03s-.02-.06-.02-.06c-.03.05-.05.08-.05.08-.03.18-.02.34,0,.49v.06c-.02.27-.03.47-.02.6l-.04.57s-.03.07-.04.14c0,.07,0,.11,0,.13v.19c0,.15,0,.36.01.62v.23s0,.03,0,.03v-.03s-.03-.09-.03-.09c-.03-.15-.03-.29,0-.43-.02-.1-.03-.18-.02-.23-.03-.15-.03-.25,0-.33.02-.03.01-.09,0-.19v-.56c-.01-.1-.02-.24-.02-.42v-.06s-.01-.05,0-.1c.01-.05,0-.08-.02-.09.02-.03.01-.05-.01-.06-.03-.02-.04-.02-.04-.02l-.06-.12c0-.07.01-.14.01-.23,0-.07,0-.14-.02-.23,0-.09-.02-.23-.06-.41l-.03-.42-.05-.22-.05-.25c-.02-.08-.03-.23-.03-.45v-.03s-.02,0-.04,0c0,0,0,.01,0,.03-.01.05-.02.1-.03.17-.01.05-.02.1-.03.17,0,.39-.02.69-.07.9l.02.23s0,.03-.02.04v-.03s0-.13,0-.13c0,0-.01,0-.03,0,0,0,0-.01,0-.03v.03s-.01.2-.01.2c.01.06,0,.14-.01.23,0,.09,0,.15,0,.19v.03s0-.03,0-.03v-.16s-.03-.06-.05-.06c0,0-.01,0-.03,0,0,0,0,.01,0,.03l.02.23s0,.11,0,.19l-.03.33v.29c.01.26.01.47,0,.62v.03s0-.03,0-.03l-.09-.73v-.23c0-.06-.01-.13-.03-.19,0-.07,0-.14-.05-.22l-.05-.22v-.03s0,.03,0,.03l-.03.33-.03-.29s.02-.01,0-.03v.03c0,.07,0,.14,0,.23,0,.09-.02.18-.04.27,0,.02,0,.03-.02.04-.02,0-.03,0-.03,0v-.03c0-.07,0-.14,0-.23,0-.09,0-.15,0-.19v-.82s-.01-.3-.01-.3c0,0,0-.02-.01-.06.01-.05,0-.06-.04-.06v-.06s0-.26,0-.26c0-.04-.02-.06-.04-.06v.03s0,.1,0,.16l-.04.14s0,.03-.02.04v-.03s-.01-.33-.01-.33v-.06s-.04.04-.04.04c0,.02,0,.03-.02.04l.02.09-.02-.09-.02-1.14v-.23s0-.03,0-.03c0,0-.01,0-.03,0,0,0,0,.01,0,.03v.49s-.02.02-.02.04v-.03s-.01-.03-.01-.03l-.02-.09s-.02.06-.01.1l-.04.27s-.01,0-.03,0c0,0,0,.01,0,.03v-.06s-.02-.16-.02-.16v-.33s-.01-.03-.01-.03l-.02.07v-.06s-.03-.52-.03-.52c-.03-.54-.05-.98-.06-1.33l-.1-1.35-.04-.48c-.01-.06-.04-.09-.08-.08-.18.08-.47.19-.88.32-.13.03-.29.08-.49.17l-1.25.4c-.37.12-.64.23-.82.31-.04,0-.09.05-.14.13-.21.24-.39.55-.55.94l-.1.12c-.11.2-.29.56-.55,1.07-.17.34-.28.58-.33.73-.02.03-.07.15-.15.36l-.02.07c.04.08.02.15-.05.21l-.06.18-.18.4s0,.07-.05.08c-.05.08-.07.11-.07.11-.09.17-.2.49-.32.95-.02.03-.03.11-.05.24l-.02.07v-.06s-.04-.13-.04-.13l.09-.64-.02-.09s-.03-.09,0-.16c.02,0,.03,0,.03,0,0-.02,0-.03,0-.03.02-.09.04-.23.04-.4.02-.03.02-.08,0-.16-.02-.08-.01-.15.02-.2l.34-.86.04-.14-.1.12s-.06.08-.07.15c-.03.07-.05.12-.07.15-.09.19-.17.33-.24.41l-.04.14-.04.11s-.06.02-.06.04l-.04-.02c.03-.05.05-.08.05-.08.02,0,.03,0,.03,0,0-.02,0-.03,0-.03-.01-.06.02-.18.09-.35.06-.14.08-.24.07-.28.01-.13.02-.2.02-.2.02,0,.03,0,.03,0-.03-.02-.04-.02-.04-.02-.02,0-.03.02-.02.04-.04.14-.1.31-.19.5l-.02.07c-.01.13-.04.24-.06.31-.03.07-.09.23-.19.47,0,.02,0,.03,0,.03-.02,0-.03,0-.03,0v-.03s.03-.14.03-.14c-.04-.17,0-.36.1-.58.09-.19.14-.35.16-.46,0-.11.02-.19.08-.25h.03s-.03-.08.01-.11c.02-.03.03-.05.05-.08v-.13c.04-.05.05-.09.05-.11v-.03s-.04,0-.04,0l-.07.11c-.02.11-.07.19-.15.23-.04,0-.07.07-.09.18l-.06.04.02-.07c0-.07.04-.17.1-.32.07-.08.13-.27.17-.56l.02-.07.02-.07-.06.04c-.08.13-.27.5-.58,1.11l-.02.04v-.06s.28-.59.28-.59l.02-.2-.07-.02s-.05.03-.08.08c0,.02,0,.04.01.06-.02,0-.04.02-.06.04l-.03-.12c.03-.05.06-.12.08-.21.05-.08.04-.12-.03-.12h-.03s-.06.05-.06.05l.02-.07c.02-.09.05-.16.08-.21l.1-.32.16-.3.28-.52.18-.37.07-.15v-.06c-.08,0-.11-.02-.09-.05.02-.03.03-.05.05-.08l.02-.04.02-.04v.06s.02.03.02.03h.03s.03-.06.05-.08c.04-.03.07-.06.11-.09l.04-.14v-.03s-.08-.02-.08-.02c0,.02-.01.05-.05.08v.13s-.02,0-.07.01v-.03c.07-.17.11-.27.13-.29.01-.05.03-.09.07-.15.03-.05.05-.1.07-.15.04-.03.07-.09.09-.18.05-.16.08-.27.1-.32l-.04-.02s-.01,0-.03,0c0,0,0-.01,0-.03v-.06s.04-.04.04-.04l.1-.32.15-.2.47-1.02.24-.41.26-.48.02-.04v-.06s-.04.02-.04.04l-.26.48-.13.16s0,.03-.02.04v-.06s.07-.21.07-.21c0-.02,0-.03,0-.03.02-.03.01-.05-.01-.06v-.03c.04-.1.07-.19.1-.28.04-.12.08-.23.13-.32.23-.44.35-.66.35-.66l.19-.47c.09-.28.2-.52.33-.73l.31-.82c.04-.1.1-.21.16-.33.06-.12.12-.28.19-.47l.32-.79c.14-.36.22-.56.23-.61.07-.1.12-.22.15-.36.08-.24.15-.4.22-.51.04-.1.09-.22.15-.36.06-.14.11-.31.15-.49.02-.11.08-.25.18-.4.1-.15.17-.27.22-.34l.1-.12c.03-.05.09-.09.17-.1s.14-.04.18-.07c.16-.08.26-.12.3-.13.08-.02.19-.02.33,0,.05.01.12,0,.23-.02.04,0,.09-.02.16-.03.06-.01.11-.01.13,0,.03.02.06.02.1.01.07,0,.15,0,.26,0,.13,0,.24,0,.33.03.08.05.21.1.39.14l.24.05.12.1c.09,0,.15.02.18.06.05.01.08.02.1.01l.11.04.29.3v.06s-.09.12-.09.12c-.07.1-.1.21-.1.32.04.17.06.31.06.44,0,.13,0,.24,0,.33l.07.64.06.87.04.65c.05.43.08.77.09,1.03,0,.11,0,.23.01.36,0,.11,0,.22,0,.33.01.06.02.13,0,.19-.01.05-.01.1,0,.16l-.02.2c-.04.14-.06.22-.08.25l-.02.07c-.04.14-.02.37.06.71,0,.02.03.03.07.02l.09-.02-.09.05s0,.03-.02.04c-.02,0-.03.02-.02.04,0,.04.02.06.04.06.04-.03.06-.04.06-.04h.03s0,.02,0,.02l-.02.04.07.02s.1-.05.18-.07h.06s-.03,0-.02.02l-.15.07-.02.04h.03s.38-.06.38-.06l.16-.03s.04,0,.06-.01c.04,0,.08,0,.1.01.03.02.08.02.16,0l.4-.12h.06s-.06.03-.06.03c-.12.07-.22.11-.3.13-.02,0-.03.02-.02.04h.03s.16-.04.16-.04l.04.02h-.03s-.09.06-.15.07l-.51.21s0,.01,0,.03c0,0-.01,0-.03,0h.03s.65-.18.65-.18c.13-.03.22-.06.27-.09l.07.02h-.06s-.36.16-.36.16c-.02,0-.09.05-.2.14-.12.07-.23.11-.33.14-.04.03-.1.05-.18.07v.03s.23-.02.23-.02c.02,0,.03-.02.02-.04.03-.05.07-.07.12-.06.04,0,.07-.02.09-.02.02,0,.03,0,.04.02h-.03s0,.04-.02.04h.03s.03,0,.04.02v.03s.04,0,.04,0c0-.02,0-.03,0-.03l.06-.04.49-.17c.13-.03.22-.06.27-.09l.04.02h-.03s0,.04-.02.04h.03s.46-.14.46-.14l.23-.02s-.03.02-.02.04c-.09,0-.16.01-.22.05-.04,0-.07.02-.09.02-.06.03-.16.07-.31.1-.06.01-.11.05-.14.1h-.03s-.06.02-.06.02c-.06.01-.11.04-.15.07-.04.03-.08.05-.12.06l-.06.04s.03,0,.04.02c.02,0,.03,0,.04.02h-.03s-.03.01-.03.01h-.06s.02.11.02.11h.06s.24-.13.24-.13c.05.01.1,0,.16-.03s.1-.05.12-.06c.02,0,.03,0,.03,0h.06s-.01.02-.06.03c-.16.08-.3.13-.42.16l-.08.08s-.03.02-.02.04h.03s.41-.1.41-.1h.1s.03,0,.03,0l.4-.12c.17-.04.28-.07.34-.11l.27-.09.42-.16h.06s.07,0,.07,0h-.06s-.48.22-.48.22l-.3.13-.06.04h.06s.18-.09.18-.09c.19-.04.42-.11.71-.22.1-.02.24-.07.39-.15l.49-.17c.12-.03.22-.06.27-.09.04,0,.04,0,0,.03,0,0,0,.01,0,.03,0,0,.01,0,.03,0,.02,0,.03-.02.02-.04l.68-.18.95-.3.25-.05h.03s-.03.01-.02.03l-.24.09-.6.26-.39.15c-.08.02-.15.04-.21.08-.26.1-.45.2-.56.29l-.6.26-.76.26-.63.27-.6.23-.51.21-1.14.48s-.08.06-.14.1c-.06.01-.11.04-.15.07-.04,0-.06.03-.05.08l.02.39v.46c.02.06,0,.12-.03.17,0,0-.01,0-.03,0,0,0,0,.01,0,.03v-.03s-.02-.23-.02-.23l-.02-.23v-.1s-.02-.13-.02-.13l-.07.11v-.03s-.05-.06-.07-.12v-.03s-.03.04-.03.04v.19c.01.11.03.26.07.44-.02.03-.02.05-.02.07.02,0,.04-.02.06-.04.02,0,.02,0,0,.03l-.05.08c-.03.07-.04.16-.04.27.02.08.03.15.04.19.08.35.11.62.11.8l.03,1.04c0,.11,0,.35,0,.72.02.17.02.33,0,.49-.01.13-.02.26-.02.36.01.37,0,.69-.02.95-.03.27-.04.48-.03.63,0,.18,0,.31.02.39,0,.04.01.06.01.06.03.06.04.13.02.23l-.03.33-.07.44c.01.06.01.12,0,.16-.03.38-.04.58-.03.6-.02.03-.02.07,0,.13v.13c0,.24,0,.4-.03.5,0,.22.02.38.04.48l.04.65c.02.08.03.17.02.26,0,.09,0,.16.02.23,0,.04,0,.12-.01.23,0,.13.03.24.07.34v.03s-.05.02-.05.04c0,.04.02.07.02.09-.02.09-.03.17-.01.23h-.03s0-.02,0-.02ZM44.27,32.93l.04-.14v-.03s-.04.02-.03.04c-.03.05-.05.09-.04.11v.03s.04,0,.04,0ZM52.95,38.02s-.04-.02-.05-.09v-.13s.04,0,.04,0c.01.06.01.11,0,.13l.02.09ZM51.52,35.68s0-.03,0-.03c.02,0,.03,0,.03,0-.02-.08-.02-.17,0-.26v-.06s-.02-.03-.02-.03l-.02.04v.33s.01.03.01.03ZM51.8,35.78s.05-.03.08-.08c-.02,0-.03,0-.04-.02,0-.02,0-.03,0-.03-.04,0-.06.04-.04.11v.03ZM52.38,36.34c.03-.05.05-.08.05-.08l-.02-.09-.04.11v.06ZM51.84,35.51l.02-.07c-.01-.06-.01-.12,0-.16h.03s0,.02,0,.02c0-.02,0-.03,0-.03.02,0,.03,0,.03,0l-.08-.21v-.03s-.04.02-.03.04c-.01.13-.01.24,0,.33-.02.03-.02.07,0,.13,0,0,0,.02.01.06l.02-.07ZM51.55,34.79s-.02-.03-.04-.02v.03s0,.08,0,.16c-.01.05-.01.1,0,.16l.03-.33ZM52.42,35.45s.02-.07,0-.13h.03c-.02-.09-.04-.15-.07-.19v-.03s0,.03,0,.03v.33s.04,0,.04,0ZM51.87,34.88c.02-.09.03-.17.01-.23,0-.07,0-.12,0-.16l-.02-.09v-.03s-.04.02-.03.04v.03c-.04.08-.05.14-.01.2v.1c-.04.05-.05.11-.04.17l.04.06.05-.08ZM51.32,33.85s.02-.05.02-.07c0-.04,0-.08.01-.1v-.06s-.03.07-.03.07l-.02.07.02.09v.03s0-.03,0-.03ZM51.89,34.22v-.03c-.02-.06-.02-.12,0-.16l-.04-.02v.03s-.03.14-.03.14c-.04.03-.04.05-.02.07.03.02.04.03.04.06h.03s.02-.08.02-.08ZM51.87,33.83l.02-.07c-.02-.08-.02-.19,0-.33v-.03s-.01-.03-.01-.03h-.03s0,.47,0,.47l.04.02v-.03ZM51.31,33.2s.03-.02.02-.04v-.1s-.02-.13-.02-.13v-.06s-.03.07-.03.07c.02.1.03.18.02.23v.03ZM46.02,28.62s.06-.02.06-.04c.02-.03.02-.05.02-.07.04,0,.07-.03.09-.05s.02-.05.02-.07c.01-.05.04-.1.1-.15.05-.06.09-.11.1-.15.03-.05.04-.11.03-.17.02-.03.02-.06.01-.1h.03s0,.03.01.06c.02,0,.03-.02.02-.04.04-.03.05-.08.04-.14,0-.07.02-.11.04-.14,0,0,0-.01,0-.03,0-.02-.02-.03-.04-.02-.02,0-.04.02-.06.04,0,.02,0,.01-.04-.02v.06s0,.08-.01.17c-.04.03-.06.07-.07.11s-.03.08-.04.11c-.02,0-.03.03-.02.07.02,0,.03-.02.02-.04l.04.02s0,.07-.05.08c-.05-.01-.09,0-.12.06-.05.08-.07.11-.07.11.03.04.04.08.03.13-.01.05-.03.08-.04.11,0-.04-.03-.07-.05-.09l-.05.21h.03ZM51.56,32.85s0-.03,0-.03c.02,0,.03,0,.03,0-.02-.08-.02-.19,0-.33v-.06s-.07-.09-.07-.09v.1s0,.05-.02.1c0,.02.02.05.05.09v.19s.02.03.02.03ZM51.88,33.14v-.46s0-.03,0-.03v-.06s-.03.07-.03.07v.16s0,.33,0,.33v.03s.03-.04.03-.04ZM46.68,27.43s0-.08.01-.1v-.06s-.04.04-.04.04c-.03.05-.04.1-.04.14l.02.09.04-.11ZM51.85,32.36s0-.03,0-.03c.02-.03.02-.05.02-.07.01-.13.01-.23,0-.29.01-.13.01-.23,0-.3v-.03s0,.01,0,.03c0,0-.01,0-.03,0v.06s-.01.33-.01.33v.03s0-.03,0-.03v-.1s-.03-.06-.03-.06v.03s0,.1,0,.16c0,.04,0,.09-.04.14l.02.09s.03.03.07.02ZM46.8,27.11c.08-.04.11-.08.1-.12v-.03s-.02-.03-.04-.02c-.07.1-.1.15-.1.15v.03s.04,0,.04,0ZM51.36,31.65v-.13s-.03-.29-.03-.29v-.03s-.03.04-.03.04l.03.42v.03s.03-.04.03-.04ZM51.27,31.38c0-.18,0-.31-.02-.39v-.03s0,.03,0,.03l-.02.2v.16s0,.03,0,.03h.03ZM46.73,26.47v-.03c-.08.08-.12.14-.13.19v.03s.13-.19.13-.19ZM47.03,26.93v-.06s.02-.14.02-.14c0,0,0-.02-.01-.06l-.06.18v.06s0,.07,0,.07l.06-.04ZM51.33,31.07l.02-.04v-.06s-.03-.06-.03-.06c0,.02,0,.03-.02.04v.13s.04.06.04.06v-.06ZM51.19,30.84v-.06s-.03-.06-.03-.06c0-.02,0-.03,0-.03.02,0,.03,0,.03,0l-.04-.02s0,.01,0,.03c0,0-.01,0-.03,0l.02.09v.06s.04,0,.04,0ZM51.49,31.2c-.01-.06-.01-.12,0-.16l.02-.04h.03s0-.04,0-.04l-.04-.02-.04-.02v.03s0,.23,0,.23v.03s.01.03.01.03l.02-.04ZM46.78,26.39l.07-.15v-.03s-.04,0-.04,0l-.07.15v.03s.04,0,.04,0ZM47.14,26.71s0-.06.04-.11l-.02-.09c-.05.08-.07.11-.07.11,0,.04.03.07.05.09ZM47.07,26.53s0,.03,0,.03c.02,0,.03-.02.02-.04l.1-.12-.04-.02s-.02-.02-.03,0l-.07.11v.03ZM49.03,28.33s.05-.04.09-.05h.06s.06-.06.06-.06h-.06s-.06.03-.06.03c-.06.01-.09.04-.08.08-.05-.01-.11,0-.19,0h-.06s.07.03.07.03l.19-.04ZM51.54,30.79s.03-.02.02-.04v-.03s-.01-.03-.01-.03l-.04-.06s0,.01-.02.04c0,0,0,.01-.02.04v.03s.04,0,.04,0l.02-.04v.03s.01.03.01.03v.03ZM51.82,31.06s.03,0,.03,0c0-.02,0-.03,0-.03.01-.05.01-.1,0-.16v-.03s-.03.04-.03.04v.13s0,.06,0,.06ZM47.24,26.39c.03-.05.05-.09.04-.11l-.03-.13c-.03.05-.05.09-.04.11l.03.13ZM47.41,26.12s.02-.04.07-.11c-.07-.03-.11-.05-.11-.07-.03.05-.05.08-.05.08-.02.03-.02.05-.02.07,0,.02.02.04.04.06l.04.06.02-.07ZM51.82,30.73s0-.03.02-.04c.02,0,.03-.02.02-.04v-.26s-.03-.19-.03-.19l-.04-.02v.03c.03.1.03.18.02.23v.03c.02.06.01.13-.01.2v.06ZM51.51,30.08s-.02-.03-.04-.02l-.06.04.04.06.05-.08ZM47.51,25.97c.03-.05.05-.08.05-.08l-.04-.02s-.06.02-.06.04l.04.06ZM47.22,26.03l.08-.21.2-.3v-.03s-.04,0-.04,0l-.16.33-.12.22v.03s.03-.04.03-.04ZM47.57,25.83l.05-.08s.07-.1.08-.21l.06-.18.06-.18s.03-.02.02-.04h-.03s-.04.06-.08.09c-.04.03-.04.07,0,.13-.03.05-.06.08-.08.08-.02,0-.04.02-.06.04-.02.03-.02.05-.02.07.02.08,0,.13-.04.14-.02.03-.02.06-.01.1l.04.02ZM47.51,24.96l.05-.08s-.03,0-.04-.02l-.07.15v.03s.06-.08.06-.08ZM47.73,25.04l.09-.18v-.03s-.04,0-.04,0l-.05.21s-.08.04-.11.09c-.03.05-.04.1-.04.14h.03s.12-.23.12-.23ZM47.95,25.02l.05-.21v-.03s-.04,0-.04,0l-.09.18.03.13.05-.08ZM48.94,27.43s.03,0,.04.02c.02,0,.04-.02.06-.04l.7-.25.69-.15c.05-.06.08-.09.07-.11l-.02-.09-.1-.76-.06-.44c0-.07,0-.14-.02-.23l-.03-.13-.05.08v.03s-.5.96-.5.96c-.07.1-.12.17-.15.2-.06.03-.12.1-.18.2l-.1.28c-.02.09-.05.16-.08.21-.07,0-.12.01-.15.07-.02.03-.04.05-.08.08,0,.04,0,.06-.02.07ZM48.21,24.54s.03,0,.03,0c0-.02,0-.03,0-.03.03-.05.05-.09.04-.11.03-.05.06-.12.08-.21v-.06s-.03-.06-.03-.06l-.02.07-.02.07s-.03.06-.04.11c0,.02-.01.04-.06.04v.03s.01.08,0,.1v.03s.01.03.01.03ZM50.95,26.73s.05-.06.05-.08l-.03-.16.02-.07s-.05.04-.09.05v.13s0,.06,0,.06l.04.06ZM50.8,26.66l.02-.5s-.02-.03-.04-.02v.03s0,.26,0,.26c.02.08.02.16.02.23v.03s0-.03,0-.03ZM48.43,24.04l.07-.15-.04-.06h-.03s0,.08-.03.18v.06s.04-.04.04-.04ZM51.06,26.67s.03-.03.02-.07c0-.09,0-.19-.04-.32v-.06s-.04.04-.04.04l.06.41.02.09-.02-.09ZM50.94,26.4l.04-.14-.04-.06-.02.07s-.05.07-.04.11v.03s.07-.01.07-.01ZM51.34,26.71s.06-.02.06-.04c.02,0,.02-.01,0-.03,0-.02,0-.03,0-.03-.05-.01-.06-.06-.03-.16,0-.02,0-.02.03,0h.03s-.02-.04-.04-.03c-.06-.05-.07-.11-.03-.16v-.06s-.05-.02-.05-.02v.03s-.01.06,0,.1c0,.02,0,.04-.02.07l.06.28v.06ZM51.33,25.63s-.01-.06-.01-.06c0-.02-.03-.03-.07-.02,0-.02-.01-.02-.03,0l.07.02.04.06v.06s0-.06,0-.06ZM52.06,26.29v-.13s0-.06,0-.06c-.03.05-.05.08-.05.08,0,.02,0,.04-.02.07,0,.02.02.04.04.06,0,.04.02.06.04.06v-.06ZM50.86,25.11s.01-.04,0-.03v-.33s-.02,0-.04,0c0,0,0-.01,0-.03v.03c0,.07,0,.16.04.29v.06ZM51.74,25.71l.02-.07s-.02-.03-.04-.02c0-.02,0-.04-.01-.06v.06s0,.06,0,.1l.04.06v-.06ZM53.27,25.37s0-.03,0-.03c.02,0,.03,0,.03,0,.04-.14.05-.23.04-.27l-.13-.59v-.03s0,.03,0,.03l.06.74v.13s0,.03,0,.03ZM56.1,26.49c.07-.06.13-.09.17-.1.02-.03.03-.03.03,0,.02,0,.04,0,.06-.01l.07.02h-.06c-.08.03-.14.06-.18.09l-.09.02ZM56.97,37.14c0-.11-.05-.16-.13-.17-.03-.02-.03-.03,0-.03.03-.05.04-.1.04-.14-.03-.04,0-.09.1-.15.02,0,.03-.02.02-.04h-.03s-.04-.02-.04-.02h.03s.06-.05.04-.11l.06-.04.3-.26c.03-.05.06-.08.08-.08h-.13c-.21.04-.38.07-.51.07l-.07-.02.02-.07s.03-.05-.01-.06v-.03s.02-.02.02-.04c.06-.01.15-.05.27-.12.02,0,.03-.02.02-.04h-.06c-.15.05-.26.08-.34.12h-.06s-.06.06-.06.06l.02-.07v-.03s-.04,0-.04,0l-.16.03h-.03s0-.06.02-.06c0-.02,0-.03,0-.03.02,0,.03,0,.03,0,.14-.05.35-.15.62-.3l.12-.06.02-.04-.04-.02-.15.07s-.01,0-.03,0c0,0,0-.01,0-.03l.02-.04.55-.32.1-.12.11-.09c.07-.06.14-.12.19-.17.08-.04.16-.09.23-.15.02,0,.03-.02.02-.04h-.06c-.12.08-.19.12-.24.13h-.06s-.12.04-.12.04c-.18.06-.4.16-.65.31-.2.09-.34.16-.41.22l-.09.02-.16.03h-.03s.02-.03.02-.03l.35-.21s.02-.03.05-.08l-.09.02c-.12.07-.21.1-.27.09-.08.02-.17.05-.27.09-.1.06-.16.1-.21.11h-.06s-.1,0-.1,0h.06s.24-.1.24-.1l.47-.23.38-.21s.07-.03.09-.05c.04-.03.06-.06.08-.08.04,0,.1-.04.17-.1.04,0,.08-.04.11-.09-.03-.06-.08-.05-.12.03h-.03s0-.03.02-.03c.02-.03.06-.04.12-.06l.12-.06s.03,0,.03,0c0-.02,0-.03,0-.03l-.04-.02s-.03.02-.02.04h-.1s.06-.06.06-.06l.4-.25c.12-.07.24-.15.37-.24l.02-.04h-.06c-.09.1-.16.13-.21.09-.02,0-.04-.01-.04-.06-.01-.06,0-.11.04-.14.06-.03.1-.05.12-.06l.41-.35.24-.25c.13-.09.26-.21.38-.35l.41-.38c.31-.39.45-.58.44-.55.18-.17.3-.31.37-.41l.3-.43.35-.5.21-.37c0-.07.04-.15.11-.25.14-.36.22-.56.23-.61.06-.21.06-.37,0-.49v-.06s-.03-.06-.03-.06l-.02.07-.07.11h-.03s0-.02,0-.02c.02-.03.02-.06.01-.1l-.04-.06v-.06c-.03-.06-.05-.09-.1-.08-.09,0-.2.01-.35.04h-.13s-.11-.01-.19,0c-.06.01-.12.01-.16,0-.05-.03-.08-.06-.08-.08,0-.04,0-.07.05-.08.02-.03.01-.04,0-.03,0-.02-.02-.03-.04-.02-.03-.02-.07-.04-.15-.07-.08-.05-.15-.05-.23-.01-.02,0-.03,0-.03,0,0-.02,0-.03,0-.03-.06-.05-.1-.05-.13,0-.02.03-.03.04-.06.04l-.09.05h-.03c-.01.05-.03.08-.05.08-.03-.02-.04-.02-.04-.02-.1-.04-.18-.03-.25.05l-.1.12c-.03.05-.06.07-.09.05,0,0-.04-.02-.11-.07l-.05-.09-.04-.06c-.03-.06-.09-.1-.16-.13-.08-.05-.14-.08-.18-.09-.07-.03-.11-.05-.11-.07-.02,0-.03,0-.03,0,.02-.03.02-.04.02-.04v-.06s-.01.01,0,.03c0,0-.01,0-.03,0l-.04-.02s-.02-.03-.04-.02l-.28-.07s-.09-.02-.14-.04c-.05-.01-.09-.03-.15-.07-.13-.01-.21-.05-.22-.12,0-.02-.02-.03-.04-.02l-.22-.12-.07-.02s-.04-.06-.06-.12l.09-.02s.06-.02.06-.04c.01-.05,0-.08-.02-.09-.03-.04-.04-.07-.02-.09s.01-.05-.01-.06c0-.02-.02-.03-.04-.02-.05-.03-.08-.06-.08-.08,0-.04,0-.07.05-.08l.11.04h.03s-.02-.04-.04-.03c-.03-.02-.06-.02-.1-.01l-.08-.08-.04-.06s.03,0,.03,0c.02-.03.04-.03.06-.01.14.04.22.06.25.08.05.01.08.02.1.01.02,0,.04-.03.05-.08h.03s0,0,0,.02c0,0,.01,0,.03,0,0,.04.02.06.04.06l.09-.02.12-.06s.04,0,.06-.01c.04,0,.07,0,.08.05h.03s-.08-.09-.08-.09c-.03-.04-.04-.06-.04-.06.02,0,.02-.01,0-.03,0-.02,0-.03,0-.03l-.14-.04s-.04,0-.06.01c-.03-.02-.04-.05-.05-.09h-.03s-.02.04-.02.04c.03.02.02.03-.02.04l-.16.03c-.08.04-.17.03-.27-.04-.05-.03-.08-.04-.1-.01l-.07-.02s0-.06.02-.07c0-.02.01-.04.06-.04.02,0,.03,0,.03,0,0-.02,0-.03,0-.03h-.03s-.06.02-.06.02c0,0,0,.01-.02.04-.02,0-.03,0-.04-.02-.02,0-.04-.01-.04-.06v-.06c-.06-.01-.08-.02-.08-.02.02,0,.04,0,.06-.01.02,0,.04-.02.06-.04.04-.03.04-.06.01-.1h-.03c-.01.05-.02.04-.04-.02h-.06c-.03.06-.07.06-.1,0,0-.02-.03-.05-.08-.08,0-.02-.02-.03-.04-.02,0-.02,0-.03.02-.04.02,0,.03,0,.03,0,0-.02,0-.03,0-.03l-.1-.17.02-.07.02-.07h-.03s-.03.01-.03.01c-.03-.02-.04-.05-.05-.09-.01-.06-.01-.11,0-.13s.02-.05.02-.07c0-.02,0-.04-.01-.06l-.06.04-.02.04-.04-.02.03-.17.02-.07s-.03-.04-.01-.06c.01-.05.02-.08.01-.1.02,0,.04.01.04.06v.1s.02,0,.02,0c.05-.08.07-.16.08-.25.05-.18.11-.32.18-.4.07-.1.1-.15.1-.15-.03-.06-.03-.1,0-.13.05-.06.09-.1.1-.12.02-.09.13-.31.32-.66.02-.03,0-.05-.05-.09,0-.02-.02,0-.06.04,0,0,0,.01,0,.03,0,0-.01,0-.03,0-.08.02-.15.09-.18.2l-.02.07-.2.3s0,.03-.02.04c-.02,0-.04.02-.06.04-.04,0-.06.02-.06.04-.06.14-.11.24-.16.3,0,.02,0,.03-.02.04v-.03c-.01-.13.06-.36.2-.7v-.03s-.04,0-.04,0c-.06.01-.12.07-.16.17-.03.07-.06.11-.1.12,0,0,0,.01,0,.03,0,0-.01,0-.03,0l.02-.07.05-.08c.03-.05.05-.11.06-.18.01-.05.06-.13.14-.26.03-.07.07-.14.12-.19,0-.04-.02-.06-.04-.06,0-.04,0-.08.01-.1l.35-.5.28-.39.18-.2.22-.34c.12-.24.23-.41.32-.49.02,0,.03,0,.03,0,0-.02,0-.03,0-.03l.14-.13c.07-.1.12-.17.15-.2l.33-.43.14-.13c.18-.26.39-.49.6-.69l.28-.39.47-.53.43-.45c.07-.06.16-.17.26-.32l.19-.17.59-.62.41-.38.25-.22c.11-.11.19-.18.25-.22.03-.05.09-.11.16-.17l.16-.17c.11-.11.19-.18.25-.22.07-.06.26-.18.55-.35.08-.04.19-.07.34-.11.25-.05.48-.06.68-.02.13.01.21.02.23.01.3-.02.54.02.72.14l.25.11c.29.05.48.16.56.34.01.06.05.11.1.14.05.01.08.03.11.04l.18.06c.21.06.37.16.49.29l.18.22c.03.06.07.15.09.27l.07.34-.02.2-.12.49c-.01.13-.04.23-.07.28v.03s.04.08,0,.13c-.02.03-.02.05-.02.07l-.15.36-.04.27v.03s0-.03,0-.03l-.04-.02s-.01,0-.03,0c0,0,0,.01,0,.03-.05.08-.08.17-.1.28l-.24.54-.47.99-.27.58s-.09.25-.23.61c.01.06,0,.13-.02.2,0,.07-.02.12-.03.17,0,0,0,.01,0,.03,0,0-.01,0-.03,0-.04.03-.07.08-.1.15,0,.07-.03.13-.06.18-.07.1-.1.18-.12.22-.04.1-.03.2.04.32.03.02.06.05.09.11.03.06.05.1.06.12,0,.04,0,.07-.05.08l-.08.08s-.06.02-.06.04c-.06.01-.11.05-.14.1-.11.11-.19.16-.26.15-.08.02-.2,0-.34-.06-.09-.02-.23-.04-.4-.04l-.18-.06c-.42-.13-.73-.26-.94-.39l-.23-.15c-.14-.04-.22-.06-.25-.08-.23-.15-.36-.25-.39-.31-.14-.14-.21-.31-.21-.51-.03-.12-.04-.22-.03-.29,0-.18.02-.33.03-.47,0-.04-.02-.09-.03-.16,0-.07.02-.15.05-.24l.09-.48.02-.07h-.06s-.18.22-.18.22l-.51.5c-.18.17-.3.31-.37.41-.05.06-.09.12-.12.19-.11.11-.18.2-.23.28-.03.05-.09.11-.16.17-.07.06-.14.13-.18.2,0,.02,0,.03-.02.04-.02,0-.04.02-.06.04l-.25.35-.2.27c-.16.25-.24.38-.24.38-.11.11-.24.29-.4.55,0,.02,0,.03-.02.04v-.03s.2-.41.2-.41l.16-.3s.03-.03.02-.07l-.06.04c-.11.18-.21.3-.28.36-.05.08-.17.3-.38.67-.05.08-.1.21-.14.39l-.04.11s0,.01-.02.04c0,0,0-.01,0-.03-.04,0-.07.03-.09.05l-.15.36c-.02.09-.03.17-.01.23l.04.02s.03-.02.02-.04l.02-.07s.07-.09.09-.18l.08-.21.07-.15h.03s0,.02,0,.02l-.16.33c-.02.09-.04.23-.04.4-.02.03-.01.05.01.06.03.02.05.02.07.02.08-.02.14-.02.16,0,.04,0,.06,0,.07.02h-.03c-.08.02-.13.05-.15.07l-.06.04.04.06h.13s.07.02.07.02c.06-.03.13-.04.23-.02v.03s0,.01.01.03c0,0-.01,0-.03,0l-.16.03-.06.04s.03,0,.04.02l.13-.03s.06,0,.11.04l-.09.05h-.06c-.03.06-.05.09-.05.09l.07.02.07.02-.09.02-.09.02-.06.04.07.02h.06s.08-.04.13,0c.07,0,.11,0,.13,0l.12-.03c.06-.01.1,0,.11.04l.07.02h.13s.03,0,.03,0l.09-.02.38-.05.04.02s.02.06.04.06c.04,0,.07-.02.09-.02.04,0,.08,0,.1.01s.04.02.04.02c.02-.03.02-.05.02-.07,0-.02,0-.03,0-.03.02-.03.02-.04.02-.04h.82c.06-.03.09-.06.08-.1v-.06s.06.05.06.05v.06c.06.01.11.01.18,0,.06-.01.12-.01.16,0l.28.07.14.04s.09,0,.14.04l.04.06-.02-.09v-.03s.06-.01.06-.01l.04.02s.06,0,.11.04c-.04,0-.07.03-.09.05-.04,0-.04.03.01.06l.07.02s.03,0,.04.02c0,0,0,.01-.02.04-.02.03,0,.06.02.09.03.02.05.02.07.02.06-.03.1-.03.13,0,.05.03.09.06.11.07.08.05.14.07.18.06.02,0,.03,0,.04.02,0,.02.02.03.04.02.02,0,.03,0,.03,0,.06.05.07.04.06-.04h.03s.03-.01.03-.01c.06.07.17.16.32.26v.03s-.02,0-.02,0l-.07-.02.02.09h.03c.08-.05.16-.03.24.04l.07.02-.04-.06-.04-.06-.13-.14v-.06s.02-.04.04-.04c.02,0,.03,0,.03,0,.03.06.07.09.12.1.07,0,.11.02.14.04.16.03.27.12.32.26l.19.25s0,.02.01.06c.03.04.04.07.02.09,0,.09.02.17.05.25l.04.06v.03s.07,0,.08.05c.03.02.04.03.04.06l.08.08v.06c0,.16,0,.25-.03.27-.05.06-.07.11-.06.18.03.06.09.1.16.13.05.01.06.03.04.06,0,.02,0,.03-.02.04-.03.05-.06.13-.08.25,0,.02,0,.04-.02.07-.02,0-.02.01,0,.03-.04.03-.05.08-.04.14.03.04.04.07.02.09-.03.07-.05.13-.06.18-.01.05-.02.08-.01.1l-.1.28-.18.4c-.07.17-.11.26-.1.28-.02.03-.07.15-.15.36l-.12.22c-.07.1-.09.17-.08.21-.07.1-.16.27-.28.52-.11.22-.21.39-.31.53l-.5.73-.32.33c-.1.15-.18.26-.26.32-.13.12-.28.25-.47.4-.16.17-.35.34-.57.52-.33.29-.63.52-.9.69-.13.09-.26.17-.38.21-.1.04-.18.08-.24.12-.06.03-.14.06-.24.09l-.14.1-.09.02h-.06c-.05.07-.15.12-.29.18-.12.05-.21.09-.27.12h-.06s-.04-.01-.04-.01h.03s.06-.05.06-.05l.41-.22.06-.04s.03-.06.06-.04c.01-.05.04-.06.09-.05.05.01.08.02.1.01.05-.06.16-.12.32-.2l.05-.08h-.1s-.09.03-.16.02c-.06.01-.11.02-.16.03l-.29.16s-.12.05-.24.12c-.04,0-.07.03-.09.05,0,.02,0,.03-.02.04l.04.02.04.06h-.03c-.05-.03-.09-.02-.13.03l-.22.05s-.05,0-.1-.01c-.02,0-.04.02-.06.04-.03.05-.08.08-.14.1-.06.03-.11.06-.15.07-.08.04-.21.08-.4.12l-.14.13s-.03.02-.02.04c.02,0,.03,0,.04.02.02,0,.04-.02.06-.04.02,0,.03.02.01.06l-.09.05-.09.02c-.08.02-.11.05-.08.08,0,.04,0,.08-.04.11-.04.03-.07.04-.09.02ZM57.21,37.22s-.02-.03-.04-.02c.03-.05.05-.08.05-.08l.07.02-.08.08ZM58.79,36.19s-.03,0-.04-.02c.02,0,.03-.02.02-.04l.13-.03-.11.09ZM56.78,34.92c.06-.01.1-.03.12-.06l.06-.04h-.06c-.06.03-.1.05-.12.07h-.03s.04.03.04.03ZM56.81,34.59h.03c.07-.07.14-.1.21-.12h.03s-.08.08-.08.08l-.16.03h-.03ZM56.87,34.41s-.01,0-.03,0c0,0,0-.01,0-.03h.03s.12-.07.12-.07c.02,0,.03,0,.04.02h-.03s-.05.05-.09.06h-.03ZM57.37,34.63c.12-.05.23-.11.32-.2l.15-.07s.03-.02.02-.04h-.03s-.03.01-.03.01c-.1.04-.24.13-.43.26-.02,0-.03.02-.02.04h.03ZM58.22,34.15s.1-.04.17-.1l-.04-.02s-.05.02-.09.05c-.04.03-.05.06-.05.08ZM58.53,33.95c.06-.01.12-.05.17-.1.07-.06.13-.1.17-.13.02,0,.03-.02.02-.04v-.03s-.04,0-.04,0l-.2.14c-.11.09-.18.14-.2.14l-.06.04h.06s.06-.03.06-.03ZM57.98,33.65s.06-.02.12-.06c.08-.04.12-.08.14-.13l.09-.05.06-.04h-.03s-.09.03-.09.03l-.02.07s-.09.03-.15.07c-.06.03-.11.07-.14.1v.03s.04,0,.04,0ZM59.33,33.39l-.04-.06-.1.12h.03s.12-.07.12-.07ZM59.38,33.31s.02-.03.05-.08h-.03s-.02.03-.05.08h.03ZM59.38,33.02s.06-.03.05-.08v-.03s-.04.02-.03.04c-.02,0-.03.02-.02.04,0,0-.01,0-.03,0,0,0,0,.01,0,.03h.03ZM59.82,32.95l-.04-.06h-.03s-.07.15-.07.15v.03s.14-.13.14-.13ZM59.95,32.93s.03,0,.03,0c0-.02,0-.03,0-.03v-.06s-.03,0-.08.01c-.02,0-.03-.02-.01-.06,0,0-.01,0-.03,0,0,0,0,.01,0,.03l-.02.07s0,.01,0,.03c0,0,.01,0,.03,0h.03s.03,0,.04.02ZM59.75,32.64v-.03s-.05.04-.09.05c-.02,0-.04.02-.06.04v.03s.04.02.04.02l.1-.12ZM60.1,32.73v-.03s-.08-.02-.08-.02l-.08.08s0,.01,0,.03c0,0,.01,0,.03,0l.12-.06ZM60.32,32.52l-.04-.02s-.02-.03-.04-.02c.02,0,.03-.02.02-.04.04,0,.1-.04.17-.1l.02-.04s-.08-.02-.16,0l-.07.11-.09.18v.06s.18-.13.18-.13ZM60.65,32.12l-.08-.05s-.06.03-.05.08c0,.02,0,.03,0,.03.02,0,.03,0,.03,0l.09-.05ZM60.77,31.89h-.03s-.06.04-.05.08c0,0,0,.02.01.06h.03s.04-.15.04-.15ZM60.94,31.76s-.03-.06-.08-.05h-.03s.09.12.09.12l.02-.07ZM61.15,31.52s-.02-.05.01-.1c.04,0,.06-.03.05-.08l-.04-.02s-.03.05-.05.08c-.02,0-.04.02-.06.04-.01.05-.04.08-.07.11-.04,0-.06.03-.05.08l.08.05.13-.16ZM60.98,31.19l-.07-.02-.06.04c.05.03.08.05.08.05l.05-.08ZM61.56,30.84c.06-.01.09-.04.08-.08v-.03c.08-.02.12-.06.13-.13,0-.02,0-.03,0-.03.02,0,.03,0,.03,0l.02-.07h-.06s-.13.17-.13.17v.03s.02.06.02.06h-.06s-.05.09-.05.09h.03ZM62.16,30.77c.03-.05.05-.09.04-.11v-.03s-.05.11-.05.11v.03ZM61.83,30.45s.06-.04.12-.06v-.06c.02-.05.04-.07.04-.04.02,0,.04-.02.06-.04.02-.03.01-.05-.01-.06v-.03s-.01-.03-.01-.03l-.04-.02-.06.04c.01.06.01.11,0,.13l-.1.12s0,.01,0,.03c0,0-.01,0-.03,0l.04.02ZM62.43,30.32v-.03s-.08.11-.08.11v.03s.08-.11.08-.11ZM57.5,27.27c.03-.05.05-.08.05-.08,0-.02-.02-.03-.04-.02l-.06.04.04.06ZM57.44,27.15s0-.08.01-.1v-.03s-.02,0-.04,0t0,0s-.08,0-.11-.04h-.1s-.03,0-.03,0l.03.13s.04.06.11.04h.03s0,.02,0,.02l.04.02.06-.04ZM62.44,30.25s.03-.05.1-.15h-.03s-.07.12-.07.12v.03ZM59,27.83l-.04-.02h-.13s-.06,0-.06,0l-.06.04.07.02s.06,0,.04.06l.07.02.1-.12ZM57.85,27.22s.03,0,.03,0c0-.02,0-.03,0-.03l-.08-.05s0,.01,0,.03c0,0-.01,0-.03,0l-.02.07-.02.04s.08,0,.1.01l.02-.07ZM62.08,30.1s.03-.02.02-.04c-.03-.04-.04-.07-.02-.09l.11-.09.04-.11v-.03s-.09-.08-.09-.08v.1s0,.06,0,.06l-.1.12c-.03.05-.05.08-.05.08l.08.08ZM59.79,28.44s-.05-.03-.15-.1l.02-.04s.05.01.08.05c.05.01.07.04.08.08h-.03ZM56.76,26.71s-.02-.03-.04-.02c-.07-.03-.09-.07-.06-.12,0-.02,0-.03.02-.04.02-.03.02-.05.02-.07.02-.03.05-.04.09-.05.04,0,.06,0,.07.02h.06s-.05.06-.05.06h-.03s-.08.01-.1,0l.03.16-.02.07ZM58.43,27.46l-.04-.02h-.03s.03.05.08.09v-.06ZM57.65,26.88l.06-.04-.07-.02s-.02-.03-.04-.02c-.02.03-.06.02-.13,0,0,0-.04-.02-.11-.07l-.07-.02s.01.06.01.06c0,0,0,.01,0,.03,0,0,.01,0,.03,0,.02,0,.03,0,.04.02h-.03s-.03.02-.02.04c0,.04.03.07.05.09l.02-.04h.06s.07,0,.07,0l.13-.03ZM56.26,25.9v-.03s.02,0,.02,0l.11.07s0,.03-.02.04l-.11-.07ZM57.26,26.6l.02-.04.02-.04s0-.06.06-.04h.03s.06-.02.06-.02h.03s0,.03-.02.03c-.02.03-.05.04-.09.05-.02,0-.04.02-.06.04h-.06ZM62.38,29.51l-.11-.04-.04.11.04.02.11-.09ZM57.23,26.31l.05-.08s-.03-.05-.08-.08l-.04-.02c-.05.08-.11.1-.18.07l-.06.04.07.02c.05.03.08.05.08.05.01.06.03.08.04.06s.03-.04.06-.04h.06ZM59.68,27.81s.05-.04.09-.05l.02-.04s-.01,0-.03,0c0,0,0-.01,0-.03-.08.02-.15.02-.19,0l-.02.04.15.07ZM58.34,26.76h.03s-.04-.03-.04-.03h-.16s-.07.03-.09.05h-.03s.04.03.04.03c.02,0,.05-.01.09-.02.04-.03.08-.03.13,0l.02-.04ZM57.72,26.3v-.06s-.09.08-.09.08c.04,0,.06,0,.07.02l.02-.04ZM57.63,26.19l-.11-.04s-.01.04-.06.04l.04.02.13-.03ZM58.08,26.45l-.07-.02s-.06.02-.06.04l.07.02.06-.04ZM56.09,25.28s-.04-.05-.05-.09c-.01-.06-.01-.11,0-.13.02,0,.03-.02.02-.04v.06c.03.06.05.1.07.12l-.02.07s0,.01-.02.04c0,0,0-.01,0-.03ZM58.66,26.72s.02,0,.06-.04l-.07-.02h-.06s-.06.03-.06.03v.03s.14,0,.14,0ZM56.57,25.38l.04-.14s-.02-.03-.04-.02v-.03s-.02.07-.02.07h.03s-.07.11-.07.11l-.04-.02s.01-.04,0-.03c-.03-.02-.04-.03-.04-.06h-.03s0,.04,0,.04v.03c0,.07.02.1.06.09l.13-.03ZM58.69,26.55s0-.03,0-.03c.02,0,.03,0,.03,0l-.04-.02-.15.07-.11-.04-.06.04.07.02.09-.02c.05.03.11.03.16,0ZM61.62,28.43c-.02-.08-.02-.15,0-.19l-.04-.02-.02.04.02.23.04.02.02-.07ZM60.45,27.41h.03s-.07-.02-.07-.02l-.28.06c-.05-.03-.08-.05-.08-.05-.1.02-.16.06-.17.1h-.06s.07.03.07.03c.11.02.18,0,.21-.08.02,0,.03-.02.02-.04,0,.07,0,.1.05.09l.27-.09ZM56.4,24.92s.03-.02.02-.04l.06-.04h.03s-.08-.06-.08-.06c0,0-.01,0-.03,0,0,0,0,.01,0,.03-.02,0-.03.02-.02.04v.06ZM56.5,24.64s-.01,0-.03,0c0,0,0-.01,0-.03-.03.05-.05.08-.05.08l.04.02.05-.08ZM56.66,24.73v-.03s-.02-.06-.02-.06l-.04-.02c-.03.05-.04.1-.04.14l.05.09.04-.11ZM61.52,27.34c.07,0,.09-.02.08-.08-.02-.08-.04-.14-.07-.18v-.03c-.11-.07-.19-.09-.25-.08-.04,0-.06.02-.06.04v.03s-.06-.02-.06-.02v-.03c-.06-.05-.13-.06-.21-.02v.06s0,.07,0,.07c-.13.03-.22.04-.29.03l-.06.04v.03s.14,0,.14,0l.07.02c-.03.05-.05.08-.05.08l-.12.03s-.06.02-.06.04h.06c.07,0,.17-.02.32-.05,0-.02,0-.03.02-.04h.03s.06-.02.06-.02c-.02.03-.02.05-.02.07.02,0,.03,0,.03,0l.09-.02.33.03ZM62.28,26.82s-.02-.06-.04-.06c-.09,0-.14-.05-.16-.13-.13-.08-.19-.12-.19-.12,0,0-.02,0-.06.01v-.03s-.04,0-.04,0l-.02.07.02.09h-.03s0-.02,0-.02c.02-.03-.01-.06-.09-.11l-.07-.02c-.11-.11-.24-.15-.39-.14l-.17-.03-.39.02h-.16s-.06.05-.06.05l.04.02.04.06h-.03s-.07-.01-.07-.01c-.04,0-.06.02-.06.04.01.06-.02.09-.11.09h-.06s-.7.1-.7.1l-.08.08s.08,0,.1.01h.13s0-.03.02-.03l-.04-.06.07.02s.02.03.04.02h.23s.03,0,.03,0h-.03s-.02.08-.02.08h.06s.06-.03.06-.03l.04.02-.06.04-.19.04h-.06c.05.05.08.06.08.06h.19s.6-.11.6-.11c.04,0,.08,0,.1.01s.06.02.1.01c.1-.06.2-.05.3.03.03-.05.06-.06.09-.02.05.01.08.02.1.01h.03s0-.06.02-.04c.02,0,.04,0,.06-.01h.06s-.01-.08-.03-.14c-.02-.08-.05-.14-.1-.17v-.06s.05-.01.05-.01l.13.17v.03s0,.1,0,.1c.07.03.11.04.11.04.02-.03.03,0,.04.06l.04.02h.06s-.04-.07-.04-.07v-.03s.02,0,.02,0c.05.03.09.05.11.04.08-.02.16.01.21.08,0,.02.02.04.04.06.02,0,.03,0,.04.02l.06-.18ZM60.07,26.12h-.19s-.03.02-.03.02c0-.02,0-.03,0-.03l.02-.04.09-.02h.46s.04.02.04.02h-.03s-.35.05-.35.05ZM62.05,26.93l-.05-.09h-.03s-.02.08-.02.08l.08.08.02-.07ZM62.58,26.98s.03,0,.03,0c0-.02,0-.03,0-.03l-.07-.18-.04-.02v.03s0,.13,0,.13c0,.02.02.04.04.06.02,0,.03,0,.04.02ZM62.32,26.68l-.11-.07s.04.08.09.11l.02-.04ZM63.53,26.35l-.08-.05.06-.04.07.02c-.03.05-.05.08-.05.08ZM65.15,18.63l-.07-.02-.06.04v.03s.03-.04.03-.04l.07.02.02-.04ZM64.78,18.28s0-.07.05-.08l-.04-.02s-.06.03-.05.08c.02,0,.03,0,.04.02ZM68.08,34.72c0-.11-.05-.16-.13-.17-.03-.02-.03-.03,0-.03.03-.05.04-.1.04-.14-.03-.04,0-.09.1-.15.02,0,.03-.02.02-.04h-.03s-.04-.02-.04-.02h.03s.06-.05.04-.11l.06-.04.3-.26c.03-.05.06-.08.08-.08h-.13c-.21.04-.38.07-.51.07l-.07-.02.02-.07s.03-.05-.01-.06v-.03s.02-.02.02-.04c.06-.01.15-.05.27-.12.02,0,.03-.02.02-.04h-.06c-.15.05-.26.08-.34.12h-.06s-.06.06-.06.06l.02-.07v-.03s-.04,0-.04,0l-.16.03h-.03s0-.06.02-.06c0-.02,0-.03,0-.03.02,0,.03,0,.03,0,.14-.05.35-.15.62-.3l.12-.06.02-.04-.04-.02-.15.07s-.01,0-.03,0c0,0,0-.01,0-.03l.02-.04.55-.32.1-.12.11-.09c.07-.06.14-.12.19-.17.08-.04.16-.09.23-.15.02,0,.03-.02.02-.04h-.06c-.12.08-.19.12-.24.13h-.06s-.12.04-.12.04c-.18.06-.4.16-.65.31-.2.09-.34.16-.41.22l-.09.02-.16.03h-.03s.02-.03.02-.03l.35-.21s.02-.03.05-.08l-.09.02c-.12.07-.21.1-.27.09-.08.02-.17.05-.27.09-.1.06-.16.1-.21.11h-.06s-.1,0-.1,0h.06s.24-.1.24-.1l.47-.23.38-.21s.07-.03.09-.05c.04-.03.06-.06.08-.08.04,0,.1-.04.17-.1.04,0,.08-.04.11-.09-.03-.06-.08-.05-.13.03h-.03s0-.03.02-.03c.02-.03.06-.04.12-.06l.12-.06s.03,0,.03,0c0-.02,0-.03,0-.03l-.04-.02s-.03.02-.02.04h-.1s.06-.06.06-.06l.4-.25c.12-.07.24-.15.37-.24l.02-.04h-.06c-.09.1-.16.13-.21.09-.02,0-.04-.01-.04-.06-.01-.06,0-.11.04-.14.06-.03.1-.05.12-.06l.41-.35.24-.25c.13-.09.26-.21.38-.35l.41-.38c.31-.39.45-.58.44-.55.18-.17.3-.31.37-.41l.3-.43.35-.5.21-.37c0-.07.04-.15.11-.25.14-.36.22-.56.23-.61.06-.21.06-.37,0-.49v-.06s-.03-.06-.03-.06l-.02.07-.07.11h-.03s0-.02,0-.02c.02-.03.02-.06.01-.1l-.04-.06v-.06c-.03-.06-.05-.09-.1-.08-.09,0-.2.01-.35.04h-.13s-.11-.01-.19,0c-.06.01-.12.01-.16,0-.05-.03-.08-.06-.08-.08,0-.04,0-.07.05-.08.02-.03.01-.04,0-.03,0-.02-.02-.03-.04-.02-.03-.02-.07-.04-.15-.07-.08-.05-.15-.05-.23-.01-.02,0-.03,0-.03,0,0-.02,0-.03,0-.03-.06-.05-.1-.05-.13,0-.02.03-.03.04-.06.04l-.09.05h-.03c-.01.05-.03.08-.05.08-.03-.02-.04-.02-.04-.02-.1-.04-.18-.03-.25.05l-.1.12c-.03.05-.06.07-.09.05,0,0-.04-.02-.11-.07l-.05-.09-.04-.06c-.03-.06-.09-.1-.16-.13-.08-.05-.14-.08-.18-.09-.07-.03-.11-.05-.11-.07-.02,0-.03,0-.03,0,.02-.03.02-.04.02-.04v-.06s-.01.01,0,.03c0,0-.01,0-.03,0l-.04-.02s-.02-.03-.04-.02l-.28-.07s-.09-.02-.14-.04c-.05-.01-.09-.03-.15-.07-.13-.01-.21-.05-.22-.12,0-.02-.02-.03-.04-.02l-.22-.12-.07-.02s-.04-.06-.06-.12l.09-.02s.06-.02.06-.04c.01-.05,0-.08-.02-.09-.03-.04-.04-.07-.02-.09.02-.03.01-.05-.01-.06,0-.02-.02-.03-.04-.02-.05-.03-.08-.06-.08-.08,0-.04,0-.07.05-.08l.11.04h.03s-.02-.04-.04-.03c-.03-.02-.06-.02-.1-.01l-.08-.08-.04-.06s.03,0,.03,0c.02-.03.04-.03.06-.01.14.04.22.06.25.08.05.01.08.02.1.01.02,0,.04-.03.05-.08h.03s0,0,0,.02c0,0,.01,0,.03,0,0,.04.02.06.04.06l.09-.02.12-.06s.04,0,.06-.01c.04,0,.07,0,.08.05h.03s-.08-.09-.08-.09c-.03-.04-.04-.06-.04-.06.02,0,.02-.01,0-.03,0-.02,0-.03,0-.03l-.14-.04s-.04,0-.06.01c-.03-.02-.04-.05-.05-.09h-.03s-.02.04-.02.04c.03.02.02.03-.02.04l-.16.03c-.08.04-.17.03-.27-.04-.05-.03-.08-.04-.1-.01l-.07-.02s0-.06.02-.07c0-.02.01-.04.06-.04.02,0,.03,0,.03,0,0-.02,0-.03,0-.03h-.03s-.06.02-.06.02c0,0,0,.01-.02.04-.02,0-.03,0-.04-.02-.02,0-.04-.01-.04-.06v-.06c-.06-.01-.08-.02-.08-.02.02,0,.04,0,.06-.01.02,0,.04-.02.06-.04.04-.03.04-.06.01-.1h-.03c-.01.05-.02.04-.04-.02h-.06c-.03.06-.07.06-.1,0,0-.02-.03-.05-.08-.08,0-.02-.02-.03-.04-.02,0-.02,0-.03.02-.04.02,0,.03,0,.03,0,0-.02,0-.03,0-.03l-.1-.17.02-.07.02-.07h-.03s-.03.01-.03.01c-.03-.02-.04-.05-.05-.09-.01-.06-.01-.11,0-.13.02-.03.02-.05.02-.07,0-.02,0-.04-.01-.06l-.06.04-.02.04-.04-.02.03-.17.02-.07s-.03-.04-.01-.06c.01-.05.02-.08.01-.1.02,0,.04.01.04.06v.1s.02,0,.02,0c.05-.08.07-.16.08-.25.05-.18.11-.32.18-.4.07-.1.1-.15.1-.15-.03-.06-.03-.1,0-.13.05-.06.09-.1.1-.12.02-.09.13-.31.32-.66.02-.03,0-.05-.05-.09,0-.02-.02,0-.06.04,0,0,0,.01,0,.03,0,0-.01,0-.03,0-.08.02-.14.09-.18.2l-.02.07-.2.3s0,.03-.02.04c-.02,0-.04.02-.06.04-.04,0-.06.02-.06.04-.06.14-.11.24-.16.3,0,.02,0,.03-.02.04v-.03c-.01-.13.06-.36.2-.7v-.03s-.04,0-.04,0c-.06.01-.12.07-.16.17-.03.07-.06.11-.1.12,0,0,0,.01,0,.03,0,0-.01,0-.03,0l.02-.07s.03-.05.05-.08c.03-.05.05-.11.06-.18.01-.05.06-.13.14-.26.03-.07.07-.14.12-.19,0-.04-.02-.06-.04-.06,0-.04,0-.08.01-.1l.35-.5.28-.39.18-.2.22-.34c.12-.24.23-.41.32-.49.02,0,.03,0,.03,0,0-.02,0-.03,0-.03l.14-.13c.07-.1.12-.17.15-.2l.33-.43.14-.13c.18-.26.38-.49.6-.69l.28-.39.47-.53.43-.45c.07-.06.16-.17.26-.32l.19-.17.59-.62.41-.38.25-.22c.11-.11.19-.18.25-.22.03-.05.09-.11.16-.17l.16-.17c.11-.11.19-.18.25-.22.07-.06.26-.18.55-.35.08-.04.19-.07.34-.11.25-.05.48-.06.68-.02.13.01.21.02.23.01.3-.02.54.02.72.14l.25.11c.29.05.48.16.56.34.01.06.05.11.1.14.05.01.08.03.11.04l.18.06c.21.06.37.16.49.29l.18.22c.03.06.07.15.09.27l.07.34-.02.2-.12.49c-.01.13-.04.23-.07.28v.03s.04.08,0,.13c-.02.03-.02.05-.02.07l-.15.36-.04.27v.03s0-.03,0-.03l-.04-.02s-.01,0-.03,0c0,0,0,.01,0,.03-.05.08-.08.17-.1.28l-.24.54-.47.99-.27.58s-.09.25-.23.61c.01.06,0,.13-.02.2,0,.07-.02.12-.03.17,0,0,0,.01,0,.03,0,0-.01,0-.03,0-.04.03-.07.08-.1.15,0,.07-.03.13-.06.18-.07.1-.1.18-.12.22-.04.1-.03.2.04.32.03.02.06.05.09.11.03.06.05.1.06.12,0,.04,0,.07-.05.08l-.08.08s-.06.02-.06.04c-.06.01-.11.05-.14.1-.11.11-.19.16-.26.16-.08.02-.2,0-.34-.06-.09-.02-.23-.04-.4-.04l-.18-.06c-.42-.13-.73-.26-.94-.39l-.23-.15c-.14-.04-.22-.06-.25-.08-.23-.15-.36-.25-.39-.31-.14-.14-.21-.31-.21-.51-.03-.12-.04-.22-.03-.29,0-.18.02-.33.03-.46,0-.04-.02-.09-.03-.16,0-.07.02-.15.05-.24l.09-.48.02-.07h-.06s-.18.22-.18.22l-.51.5c-.18.17-.3.31-.37.41-.05.06-.09.12-.12.19-.11.11-.18.2-.23.28-.03.05-.09.11-.16.17-.07.06-.14.13-.18.2,0,.02,0,.03-.02.04-.02,0-.04.02-.06.04l-.25.35-.2.27c-.16.25-.24.38-.24.38-.11.11-.24.29-.4.55,0,.02,0,.03-.02.04v-.03s.2-.41.2-.41l.16-.3s.03-.03.02-.07l-.06.04c-.11.18-.21.3-.28.36-.05.08-.17.3-.38.67-.05.08-.1.21-.14.39l-.04.11s0,.01-.02.04c0,0,0-.01,0-.03-.04,0-.07.03-.09.05l-.15.36c-.02.09-.03.17-.01.23l.04.02s.03-.02.02-.04l.02-.07s.07-.09.09-.18l.08-.21.07-.15h.03s0,.02,0,.02l-.16.33c-.02.09-.04.23-.04.4-.02.03-.01.05.01.06.03.02.05.02.07.02.08-.02.14-.02.16,0,.04,0,.06,0,.07.02h-.03c-.08.02-.13.05-.15.07l-.06.04.04.06h.13s.07.02.07.02c.06-.03.13-.04.23-.02v.03s0,.01.01.03c0,0-.01,0-.03,0l-.16.03-.06.04s.03,0,.04.02l.12-.03s.06,0,.11.04l-.09.05h-.06c-.03.06-.05.09-.05.09l.07.02.07.02-.09.02-.09.02-.06.04.07.02h.06s.08-.04.13,0c.07,0,.11,0,.13,0l.13-.03c.06-.01.1,0,.11.04l.07.02h.13s.03,0,.03,0l.09-.02.38-.05.04.02s.02.06.04.06c.04,0,.07-.02.09-.02.04,0,.08,0,.1.01.03.02.04.02.04.02.02-.03.02-.05.02-.07,0-.02,0-.03,0-.03.02-.03.02-.04.02-.04h.82c.06-.03.09-.06.08-.1v-.06s.06.05.06.05v.06c.06.01.11.01.18,0,.06-.01.12-.01.16,0l.28.07.14.04s.09,0,.14.04l.04.06-.02-.09v-.03s.06-.01.06-.01l.04.02s.06,0,.11.04c-.04,0-.07.03-.09.05-.04,0-.04.03.01.06l.07.02s.03,0,.04.02c0,0,0,.01-.02.04-.02.03,0,.06.02.09.03.02.05.02.07.02.06-.03.1-.03.13,0,.05.03.09.06.11.07.08.05.14.07.18.06.02,0,.03,0,.04.02,0,.02.02.03.04.02.02,0,.03,0,.03,0,.06.05.07.04.06-.04h.03s.03-.01.03-.01c.06.07.17.16.32.26v.03s-.02,0-.02,0l-.07-.02.02.09h.03c.08-.05.16-.03.24.04l.07.02-.04-.06-.04-.06-.13-.14v-.06s.02-.04.04-.04c.02,0,.03,0,.03,0,.03.06.07.09.12.1.07,0,.11.02.14.04.16.03.27.12.32.26l.19.25s0,.02.01.06c.03.04.04.07.02.09,0,.09.02.17.05.25l.04.06v.03s.07,0,.08.05c.03.02.04.03.04.06l.08.08v.06c0,.15,0,.25-.03.27-.05.06-.07.11-.06.18.03.06.09.1.16.13.05.01.06.03.04.06,0,.02,0,.03-.02.04-.03.05-.06.13-.08.25,0,.02,0,.04-.02.07-.02,0-.02.02,0,.03-.04.03-.05.08-.04.14.03.04.04.07.02.09-.03.07-.05.13-.06.18-.01.05-.02.08-.01.1l-.1.28-.18.4c-.07.17-.11.26-.1.28-.02.03-.07.15-.15.36l-.12.22c-.07.1-.09.17-.08.21-.07.1-.16.27-.28.52-.11.22-.21.39-.31.53l-.5.73-.32.33c-.1.15-.18.26-.26.32-.13.12-.28.25-.47.4-.16.17-.35.34-.57.52-.33.29-.63.52-.9.69-.13.09-.26.17-.38.21-.1.04-.18.08-.24.12-.06.03-.14.06-.24.09l-.14.1-.09.02h-.06c-.05.07-.15.12-.29.18-.12.05-.21.09-.27.12h-.06s-.04-.01-.04-.01h.03s.06-.05.06-.05l.41-.22.06-.04s.03-.06.06-.04c.01-.05.04-.06.09-.05.05.01.08.02.1.01.05-.06.16-.12.32-.2l.05-.08h-.1s-.09.03-.16.02c-.06.01-.11.02-.16.03l-.29.16s-.12.05-.24.12c-.04,0-.07.03-.09.05,0,.02,0,.03-.02.04l.04.02.04.06h-.03c-.05-.03-.09-.02-.13.03l-.22.05s-.05,0-.1-.01c-.02,0-.04.02-.06.04-.03.05-.08.08-.14.1-.06.03-.11.06-.15.07-.08.04-.21.08-.4.12l-.14.13s-.03.02-.02.04c.02,0,.03,0,.04.02.02,0,.04-.02.06-.04.02,0,.03.02.01.06l-.09.05-.09.02c-.08.02-.11.05-.08.08,0,.04,0,.08-.04.11-.04.03-.07.04-.09.02ZM68.33,34.8s-.02-.03-.04-.02c.03-.05.05-.08.05-.08l.07.02-.08.08ZM69.91,33.77s-.03,0-.04-.02c.02,0,.03-.02.02-.04l.12-.03-.11.09ZM67.89,32.5c.06-.01.1-.03.12-.06l.06-.04h-.06c-.06.03-.1.05-.12.07h-.03s.04.03.04.03ZM67.92,32.17h.03c.07-.07.14-.1.21-.12h.03s-.08.08-.08.08l-.16.03h-.03ZM67.98,32s-.01,0-.03,0c0,0,0-.01,0-.03h.03s.12-.07.12-.07c.02,0,.03,0,.04.02h-.03s-.05.05-.09.06h-.03ZM68.49,32.21c.12-.05.23-.11.32-.2l.15-.07s.03-.02.02-.04h-.03s-.03.01-.03.01c-.1.04-.24.13-.43.26-.02,0-.03.02-.02.04h.03ZM69.33,31.73s.1-.04.17-.1l-.04-.02s-.05.02-.09.05c-.04.03-.05.06-.05.08ZM69.65,31.53c.06-.01.12-.05.17-.1.07-.06.13-.1.17-.13.02,0,.03-.02.02-.04v-.03s-.04,0-.04,0l-.2.14c-.11.09-.18.14-.2.14l-.06.04h.06s.06-.03.06-.03ZM69.09,31.23s.06-.02.12-.06c.08-.04.12-.08.14-.13l.09-.05.06-.04h-.03s-.09.03-.09.03l-.02.07s-.09.03-.15.07c-.06.03-.11.07-.14.1v.03s.04,0,.04,0ZM70.44,30.97l-.04-.06-.1.12h.03s.12-.07.12-.07ZM70.49,30.89s.02-.03.05-.08h-.03s-.02.03-.05.08h.03ZM70.49,30.6s.06-.03.05-.08v-.03s-.04.02-.03.04c-.02,0-.03.02-.02.04,0,0-.01,0-.03,0,0,0,0,.01,0,.03h.03ZM70.94,30.53l-.04-.06h-.03s-.07.15-.07.15v.03s.14-.13.14-.13ZM71.06,30.51s.03,0,.03,0c0-.02,0-.03,0-.03v-.06s-.03,0-.08.01c-.02,0-.03-.02-.01-.06,0,0-.01,0-.03,0,0,0,0,.01,0,.03l-.02.07s0,.01,0,.03c0,0,.01,0,.03,0h.03s.03,0,.04.02ZM70.87,30.22v-.03s-.05.04-.09.05c-.02,0-.04.02-.06.04v.03s.04.02.04.02l.1-.12ZM71.21,30.31v-.03s-.08-.02-.08-.02l-.08.08s0,.01,0,.03c0,0,.01,0,.03,0l.12-.06ZM71.43,30.1l-.04-.02s-.02-.03-.04-.02c.02,0,.03-.02.02-.04.04,0,.1-.04.17-.1l.02-.04s-.08-.02-.16,0l-.07.11-.09.18v.06s.18-.13.18-.13ZM71.77,29.7l-.08-.05s-.06.03-.05.08c0,.02,0,.03,0,.03.02,0,.03,0,.03,0l.09-.05ZM71.88,29.47h-.03s-.06.04-.05.08c0,0,0,.02.01.06h.03s.04-.15.04-.15ZM72.05,29.34s-.03-.06-.08-.05h-.03s.09.12.09.12l.02-.07ZM72.26,29.1s-.02-.05.01-.1c.04,0,.06-.03.05-.08l-.04-.02s-.03.05-.05.08c-.02,0-.04.02-.06.04-.01.05-.04.08-.07.11-.04,0-.06.03-.05.08l.08.05.13-.16ZM72.09,28.77l-.07-.02-.06.04c.05.03.08.05.08.05l.05-.08ZM72.67,28.42c.06-.01.09-.04.08-.08v-.03c.08-.02.12-.06.13-.13,0-.02,0-.03,0-.03.02,0,.03,0,.03,0l.02-.07h-.06s-.13.17-.13.17v.03s.02.06.02.06h-.06s-.05.09-.05.09h.03ZM73.28,28.35c.03-.05.05-.09.04-.11v-.03s-.05.11-.05.11v.03ZM72.95,28.03s.06-.04.12-.06v-.06c.02-.05.04-.07.04-.04.02,0,.04-.02.06-.04.02-.03.01-.05-.01-.06v-.03s-.01-.03-.01-.03l-.04-.02-.06.04c.01.06.01.11,0,.13l-.1.12s0,.01,0,.03c0,0-.01,0-.03,0l.04.02ZM73.54,27.9v-.03s-.08.11-.08.11v.03s.08-.11.08-.11ZM68.62,24.85c.03-.05.05-.08.05-.08,0-.02-.02-.03-.04-.02l-.06.04.04.06ZM68.56,24.73s0-.08.01-.1v-.03s-.02,0-.04,0t0,0s-.08,0-.11-.04h-.1s-.03,0-.03,0l.03.13s.04.06.11.04h.03s0,.02,0,.02l.04.02.06-.04ZM73.56,27.83s.03-.05.1-.15h-.03s-.07.12-.07.12v.03ZM70.11,25.41l-.04-.02h-.13s-.06,0-.06,0l-.06.04.07.02s.06,0,.04.06l.07.02.1-.12ZM68.97,24.8s.03,0,.03,0c0-.02,0-.03,0-.03,0,0-.03-.02-.08-.05,0,0,0,.01,0,.03,0,0-.01,0-.03,0l-.02.07-.02.04s.08,0,.1.01l.02-.07ZM73.2,27.68s.03-.02.02-.04c-.03-.04-.04-.07-.02-.09l.11-.09.04-.11v-.03s-.09-.08-.09-.08v.1s0,.06,0,.06l-.1.12c-.03.05-.05.08-.05.08l.08.08ZM70.9,26.02s-.05-.03-.15-.1l.02-.04s.05.01.08.05c.05.01.07.04.08.08h-.03ZM67.87,24.29s-.02-.03-.04-.02c-.07-.03-.09-.07-.06-.12,0-.02,0-.03.02-.04.02-.03.02-.05.02-.07.02-.03.05-.04.09-.05.04,0,.06,0,.07.02h.06s-.05.06-.05.06h-.03s-.08.01-.1,0l.03.16-.02.07ZM69.54,25.04l-.04-.02h-.03s.03.05.08.09v-.06ZM68.76,24.46l.06-.04-.07-.02s-.02-.03-.04-.02c-.02.03-.06.02-.13,0,0,0-.04-.02-.11-.07l-.07-.02s.01.06.01.06c0,0,0,.01,0,.03,0,0,.01,0,.03,0,.02,0,.03,0,.04.02h-.03s-.03.02-.02.04c0,.04.03.07.05.09l.02-.04h.06s.07,0,.07,0l.13-.03ZM67.37,23.48v-.03s.02,0,.02,0l.11.07s0,.03-.02.04l-.11-.07ZM68.37,24.18l.02-.04.02-.04s0-.06.06-.04h.03s.06-.02.06-.02h.03s0,.03-.02.03c-.02.03-.05.04-.09.05-.02,0-.04.02-.06.04h-.06ZM73.5,27.09l-.11-.04-.04.11.04.02.11-.09ZM68.34,23.89l.05-.08s-.03-.05-.08-.08l-.04-.02c-.05.08-.11.1-.18.07l-.06.04.07.02c.05.03.08.05.08.05.01.06.03.08.04.06.02-.03.03-.04.06-.04h.06ZM70.8,25.39s.05-.04.09-.05l.02-.04s-.01,0-.03,0c0,0,0-.01,0-.03-.08.02-.15.02-.19,0l-.02.04.15.07ZM69.46,24.34h.03s-.04-.03-.04-.03h-.16s-.07.03-.09.05h-.03s.04.03.04.03c.02,0,.05-.01.09-.02.04-.03.08-.03.13,0l.02-.04ZM68.83,23.88v-.06s-.09.08-.09.08c.04,0,.06,0,.07.02l.02-.04ZM68.74,23.77l-.11-.04s-.01.04-.06.04l.04.02.13-.03ZM69.19,24.03l-.07-.02s-.06.02-.06.04l.07.02.06-.04ZM67.2,22.86s-.04-.05-.05-.09c-.01-.06-.01-.11,0-.13.02,0,.03-.02.02-.04v.06c.03.06.05.1.07.12l-.02.07s0,.01-.02.04c0,0,0-.01,0-.03ZM69.78,24.3s.02,0,.06-.04l-.07-.02h-.06s-.06.03-.06.03v.03s.14,0,.14,0ZM67.68,22.96l.04-.14s-.02-.03-.04-.02v-.03s-.02.07-.02.07h.03s-.07.11-.07.11l-.04-.02s.01-.04,0-.03c-.03-.02-.04-.03-.04-.06h-.03s0,.04,0,.04v.03c0,.07.02.1.06.09l.12-.03ZM69.8,24.13s0-.03,0-.03c.02,0,.03,0,.03,0l-.04-.02-.15.07-.11-.04-.06.04.07.02.09-.02c.05.03.11.03.16,0ZM72.74,26.01c-.02-.08-.02-.15,0-.19l-.04-.02-.02.04.02.23.04.02.02-.07ZM71.56,24.99h.03s-.07-.02-.07-.02l-.28.06c-.05-.03-.08-.05-.08-.05-.1.02-.16.06-.17.1h-.06s.07.03.07.03c.11.02.18,0,.21-.08.02,0,.03-.02.02-.04,0,.07,0,.1.05.09l.27-.09ZM67.52,22.5s.03-.02.02-.04l.06-.04h.03s-.08-.06-.08-.06c0,0-.01,0-.03,0,0,0,0,.01,0,.03-.02,0-.03.02-.02.04v.06ZM67.62,22.22s-.01,0-.03,0c0,0,0-.01,0-.03-.03.05-.05.08-.05.08l.04.02.05-.08ZM67.77,22.31v-.03s-.02-.06-.02-.06l-.04-.02c-.03.05-.04.1-.04.14l.05.09.04-.11ZM72.63,24.92c.07,0,.09-.02.08-.08-.02-.08-.04-.14-.07-.18v-.03c-.11-.07-.19-.09-.25-.08-.04,0-.06.02-.06.04v.03s-.06-.02-.06-.02v-.03c-.06-.05-.13-.06-.21-.02v.06s0,.07,0,.07c-.13.03-.22.04-.29.03l-.06.04v.03s.14,0,.14,0l.07.02c-.03.05-.05.08-.05.08l-.13.03s-.06.02-.06.04h.06c.07,0,.17-.02.32-.05,0-.02,0-.03.02-.04h.03s.06-.02.06-.02c-.02.03-.02.05-.02.07.02,0,.03,0,.03,0l.09-.02.33.03ZM73.4,24.4s-.02-.06-.04-.06c-.09,0-.14-.05-.16-.13-.13-.08-.19-.12-.19-.12,0,0-.02,0-.06.01v-.03s-.04,0-.04,0l-.02.07.02.09h-.03s0-.02,0-.02c.02-.03-.01-.06-.09-.11l-.07-.02c-.11-.11-.24-.15-.39-.14l-.17-.03-.39.02h-.16s-.06.05-.06.05l.04.02.04.06h-.03s-.07-.01-.07-.01c-.04,0-.06.02-.06.04.01.06-.02.09-.11.09h-.06s-.7.1-.7.1l-.08.08s.08,0,.1.01h.13s0-.03.02-.03l-.04-.06.07.02s.02.03.04.02h.23s.03,0,.03,0h-.03s-.02.08-.02.08h.06s.06-.03.06-.03l.04.02-.06.04-.19.04h-.06c.05.05.08.06.08.06h.19s.6-.11.6-.11c.04,0,.08,0,.1.01.03.02.06.02.1.01.1-.06.2-.05.3.03.03-.05.06-.06.09-.02.05.01.08.02.1.01h.03s0-.06.02-.04c.02,0,.04,0,.06-.01h.06s-.01-.08-.03-.14c-.02-.08-.05-.14-.1-.17v-.06s.05-.01.05-.01l.13.17v.03s0,.1,0,.1c.07.03.11.04.11.04.02-.03.03,0,.04.06l.04.02h.06s-.04-.07-.04-.07v-.03s.02,0,.02,0c.05.03.09.05.11.04.08-.02.15,0,.21.08,0,.02.02.04.04.06.02,0,.03,0,.04.02l.06-.18ZM71.18,23.7h-.19s-.03.02-.03.02c0-.02,0-.03,0-.03l.02-.04.09-.02h.46s.04.02.04.02h-.03s-.35.05-.35.05ZM73.16,24.51l-.05-.09h-.03s-.02.08-.02.08l.08.08.02-.07ZM73.7,24.56s.03,0,.03,0c0-.02,0-.03,0-.03l-.07-.18-.04-.02v.03s0,.13,0,.13c0,.02.02.04.04.06.02,0,.03,0,.04.02ZM73.43,24.26l-.11-.07s.04.08.09.11l.02-.04ZM74.64,23.93s-.03-.02-.08-.05l.06-.04.07.02c-.03.05-.05.08-.05.08ZM76.27,16.21l-.07-.02-.06.04v.03s.03-.04.03-.04l.07.02.02-.04ZM75.9,15.86s0-.07.05-.08l-.04-.02s-.06.03-.05.08c.02,0,.03,0,.04.02ZM83.65,29.6c-.1.02-.21,0-.31-.06h-.13c-.15.03-.28,0-.41-.08-.09,0-.17-.03-.25-.08-.1-.04-.21-.05-.33-.03-.02.03-.06.03-.13.03-.07,0-.12,0-.16,0l-.45-.1c-.19-.16-.38-.25-.59-.3-.14-.04-.24-.05-.3-.03-.1.02-.19-.02-.26-.14-.06-.05-.2-.1-.42-.14-.18-.03-.41-.16-.68-.41-.06-.05-.21-.25-.46-.59-.07-.12-.1-.23-.11-.34h-.03s.02-.36.02-.36c0-.18,0-.3-.01-.36v-.26c.04-.05.06-.12.06-.21,0-.09,0-.14,0-.16-.08-.05-.11-.1-.1-.14.03-.07.04-.12.04-.14-.01-.15.01-.29.07-.41.03-.18.05-.39.06-.63,0-.11.03-.28.09-.51.02-.09.09-.38.21-.86.02-.22.04-.4.08-.54.03-.16.06-.3.07-.41.07-.19.12-.41.15-.66.08-.13.1-.27.07-.44v-.13s.05-.24.05-.24c.02,0,.04-.02.06-.04.02-.03.02-.05.02-.07l.04-.11c.09-.37.14-.6.15-.69.05-.16.1-.32.13-.45.03-.16.06-.29.08-.38l.14-.55c0-.07.02-.19.05-.37.03-.18.07-.34.12-.49.06-.21.09-.38.09-.51l.08-.54c.04-.1.07-.18.08-.25,0-.09,0-.15.02-.2-.01-.06,0-.16.03-.3.04-.03.04-.06.01-.1-.01-.06-.03-.1-.06-.12l-.21-.08s-.02-.04-.04-.06c0-.04,0-.08.01-.1-.02-.1-.06-.17-.11-.21v-.06s-.04-.13-.04-.13c-.07-.14-.05-.23.07-.28.03-.05.1-.11.19-.17.23-.16.41-.34.54-.54.04,0,.06-.04.04-.11l.09-.77s0-.09-.03-.12c0-.04,0-.1,0-.16.01-.05.03-.13.05-.24.04-.14.09-.24.16-.3.11-.18.29-.29.52-.34.21-.05.37-.07.48-.07.11,0,.23.04.35.12.07,0,.14.02.21.05.07.03.14.05.21.05.03.04.09.07.18.09.11.02.19.03.24.05l.33.16c.05.03.11.04.17.03.19-.11.35-.22.45-.33.39-.3.77-.56,1.14-.77.26-.23.52-.42.79-.57.25-.16.46-.26.62-.3l.22-.05.28-.06s.08,0,.16,0c.08-.02.15,0,.21.05.03.02.06.02.1.01.04,0,.09,0,.13,0,.03.02.06.02.1.01.02,0,.03,0,.04.02h-.03s-.04.03-.06.05c0,.02,0,.03,0,.03l.04.06-.02.04.05.09.23-.02s.03.02.08.05c.03.02.05.04.08.08.03.02.06.05.09.11.01.06.04.1.09.11.05.01.08.03.11.04.02,0,.06.04.13.14.05.01.08.03.11.04.05.01.08.03.11.04.1.07.14.15.12.27.03.13.04.22.03.29l.07.18c.04.08.06.16.05.25v.4s-.06.24-.06.24h-.06c-.05-.02-.06-.08-.04-.17.02-.03.02-.06.01-.1-.01-.06-.03-.1-.06-.12-.03-.04-.06-.07-.09-.11-.03-.04-.09-.05-.17-.03-.02,0-.03.03-.02.07l-.02.07v-.06s-.06-.06-.07-.12l-.19.04-.09.02c-.07,0-.15.01-.25.05-.26.19-.47.32-.6.39-.23.16-.57.39-1.03.68-.39.22-.67.39-.84.51-.1.06-.24.16-.43.29-.19.11-.36.19-.5.24-.06.03-.12.08-.2.14-.06.03-.12.08-.2.14-.12.07-.17.1-.17.1-.12.07-.22.11-.3.13-.02.03-.05.06-.11.09-.06.01-.09.03-.09.05l-.03.17-.11.68c-.02.09-.06.22-.11.38-.04.14-.06.28-.07.41-.06.23-.1.41-.11.55-.04.14-.08.28-.14.42-.04.14-.07.29-.1.45l-.06.18v.03s.07-.01.07-.01l.34-.24c.12-.05.24-.07.34-.07.05.01.17,0,.38-.05.06-.01.11,0,.15.07.03.02.06.02.1.01.2.02.32.03.36.02v.06s-.02,0-.02,0c-.02,0-.03.02-.02.04,0,.02,0,.03-.02.04.02,0,.03,0,.04.02,0,.02.02.03.04.02l.23-.02h.03s.15.06.15.06l-.11.09c-.08.02-.13.04-.15.07h-.03s.02.04.04.03h.1s.31-.06.31-.06c.04,0,.11,0,.2.02.06.1.13.15.2.15h.19c.07,0,.11.02.11.06,0,.02,0,.03-.02.04h-.26s-.06,0-.06,0c.02,0,.03,0,.04.02.03.06.09.1.16.13.09,0,.15.01.2.02l.34.19s0,.01,0,.03c0,0,.01,0,.03,0l-.09.02s-.02-.03-.04-.02c-.02,0-.03,0-.03,0-.04-.08-.06-.1-.08-.05-.02.03-.03.04-.06.04l.06.12.18.09s0,.01,0,.03c.03.02.05.02.07.02-.04,0-.09,0-.14-.04h-.03s-.02.01-.06.02l.05.09c.18,0,.3.03.38.08l.2.18.08.05s.05.04.02.09c-.02.03-.05.04-.09.05l-.21-.05-.3-.03c-.09-.02-.11.01-.04.11v.03s-.03-.02-.03-.02c-.03-.04-.08-.04-.16,0l-.89.42-.83.41-.23.15c-.29.15-.58.29-.86.42-.1.04-.2.1-.29.16-.1.04-.22.09-.36.14-.04,0-.11.05-.21.11-.1.04-.2.08-.31.1l-.08.08c-.04.31-.08.52-.13.62l-.09.18c-.07.28-.14.6-.22.96-.04.14-.07.3-.09.48,0,.15-.05.33-.12.52-.08.63-.12,1.03-.13,1.21,0,.09,0,.19,0,.3,0,.09,0,.19.04.32,0,.09.04.11.11.07.05-.06.1-.09.14-.1.06-.03.1-.05.12-.06h.03s-.03.01-.02.03l-.28.22s-.04.02-.06.04c0,0-.01,0-.03,0l.12-.03.24-.09h.06s-.02.02-.02.02l-.26.15c-.06.03-.09.07-.1.12-.02.03,0,.07.03.12,0,.02,0,.04.01.06.02,0,.03,0,.04.02,0,.04.06.05.14.04l.24-.09c.06-.03.13-.07.21-.11.1-.06.19-.11.3-.13h.06s.04-.02.06-.03c.04,0,.08,0,.1.01.1.07.18.07.23.01l.9-.52.37-.24h.06s.1-.06.17-.12c.07-.06.15-.11.23-.15.04-.03.09-.07.17-.13.09-.09.19-.15.29-.19.02,0,.15-.09.37-.24.12-.07.2-.13.25-.19.07-.06.14-.11.2-.14.16-.06.24-.1.24-.12l.02-.07s.03,0,.04.02c0,.02,0,.03,0,.03.05-.08.08-.07.1.01.03.02.05.02.07.02.04,0,.06-.02.06-.04h.03s.06-.02.06-.02v-.03s-.02-.06-.02-.06c0-.02,0-.03.02-.04v.03s.03.09.03.09c0,0-.02.03-.05.08v.06s.02.04.03.06c.02,0,.03,0,.04.02.03.02.1.04.21.08.02,0,.03,0,.04.02.12.15.21.22.27.2.02,0,.03-.02.02-.04.02-.03.03-.04.06-.04l.02-.04s0,.01,0,.03c.02,0,.04,0,.06-.01v.03s.03.13.03.13c.02,0,.05-.03.08-.08s.05-.09.04-.11c0,0,0-.01,0-.03.02-.03.02-.05.02-.07.02,0,.03,0,.04.02,0,.02.02.03.04.02v.03c-.03.05-.02.11,0,.16.03.02.04.06.06.12.06.1.13.11.21.05.06-.03.11-.05.16-.03.08.07.1.17.07.31-.07.08-.09.16-.05.24.04.08.06.13.07.15l.07.31-.02.04s-.01,0-.03,0c-.02,0-.03,0-.04-.02-.07,0-.12-.04-.15-.1-.03-.04-.05-.04-.07-.02-.06.14-.18.26-.38.35-.1.06-.21.13-.35.21-.12.07-.24.15-.37.24-.12.07-.24.16-.37.28h-.03s-.09.01-.12.07c-.03.05-.06.08-.08.08l-.02.04-.13.03c0,.07-.04.12-.1.15s-.1.05-.12.06l-.18.07c-.12.07-.19.17-.23.31h-.03c-.06.02-.14.06-.24.12-.1.06-.17.11-.23.15l-.22.18s-.05.03-.08.08c-.06.01-.09.02-.09.02h-.06c-.06.03-.13.06-.21.12-.07.08-.13.14-.19.17l-.1.12-.2.14-.09.02ZM82.23,27.45l.05-.08h-.06c-.06.03-.1.06-.11.1l-.02.04h.06s.09-.07.09-.07ZM79.9,25.47v-.13s-.01-.03-.03-.02v.03s-.01.07,0,.13h.03ZM82.49,27.26c.1-.02.17-.05.21-.08h.03s-.04-.03-.04-.03l-.21.11h-.03s0,.02,0,.04c.02,0,.03-.02.02-.04ZM79.96,24.97c.03-.05.04-.11.03-.17v-.03s-.04,0-.04,0l-.04.14v.06s.04,0,.04,0ZM85.02,27.3s.03-.07.05-.08c.02,0,.04-.02.06-.04l.31-.23c.06-.01.13-.05.21-.11l.02-.07-.06.04c-.2.09-.34.17-.43.26-.03.05-.09.11-.16.17-.02,0-.03.03-.02.07h.03ZM84.89,26.71c.11-.09.23-.17.34-.24.12-.07.21-.13.29-.19l.06-.04s-.06.01-.06.01l-.38.21s-.08.07-.14.13c-.04.03-.08.07-.14.13h-.03s.03,0,.03,0h.03ZM85.84,25.98c.14-.07.24-.15.31-.23l.12-.03h-.16c-.11.11-.2.19-.28.23,0,0,0,.01,0,.03,0,0-.01,0-.03,0h.03ZM88.99,12.91v-.06c-.03-.06-.03-.11,0-.13h.03s.02.22.02.22h-.03s0-.02,0-.02ZM106.49,29.21c-.02-.1-.03-.18-.02-.23s0-.1-.03-.16c-.03-.06-.05-.11-.03-.16.01-.05,0-.1-.03-.16,0-.04,0-.09,0-.13l-.11-.5s-.02-.05-.05-.09c-.03-.02-.04-.03-.04-.06-.03-.02-.04-.06-.06-.12-.02-.08-.04-.14-.07-.18v-.06s-.02-.04-.03-.06c.02-.03.02-.06.01-.1v-.06s.04.12.04.12v.1s0,.03,0,.03h.03c0-.18,0-.32-.03-.43v-.03s-.03-.05-.06-.09c0-.04,0-.06.02-.07.03-.05.03-.11,0-.16-.03-.04-.05-.08-.06-.12.02,0,.02-.01,0-.03,0-.02,0-.03,0-.03.05-.16.03-.26-.06-.28-.08-.05-.11-.1-.1-.14.03-.05.05-.08.05-.08l-.04-.48c0-.2,0-.45-.03-.75l-.03-.42s0-.01,0-.03c0,0-.01,0-.03,0v.03c-.06.1-.09.15-.09.15v-.03s-.02-.06-.02-.06c-.03.05-.05.08-.05.08-.03.18-.02.34,0,.49v.06c-.01.27-.03.47-.02.6l-.04.57s-.03.07-.04.14c0,.07,0,.11,0,.13v.19c0,.16,0,.36.01.62v.23s0,.03,0,.03v-.03s-.03-.09-.03-.09c-.03-.15-.03-.29,0-.43-.02-.1-.03-.18-.02-.23-.03-.15-.03-.25,0-.33.02-.03.01-.09-.01-.19v-.56c-.01-.1-.02-.24-.02-.42v-.06s-.01-.05,0-.1c.01-.05,0-.08-.02-.09.02-.03.01-.05-.01-.06-.03-.02-.04-.02-.04-.02l-.06-.12c0-.07.01-.14.01-.23,0-.07,0-.14-.02-.23,0-.09-.02-.23-.06-.41l-.03-.42-.05-.22-.06-.25c-.02-.08-.03-.23-.03-.45v-.03s-.02,0-.04,0c0,0,0,.01,0,.03-.01.05-.02.1-.03.17-.01.05-.02.1-.03.17,0,.39-.02.69-.07.9l.02.23s0,.03-.02.04v-.03s0-.13,0-.13c0,0-.01,0-.03,0,0,0,0-.01,0-.03v.03s-.01.2-.01.2c.01.06,0,.14-.01.23,0,.09,0,.15.01.19v.03s0-.03,0-.03v-.16s-.03-.06-.05-.06c0,0-.01,0-.03,0,0,0,0,.01,0,.03l.02.23s0,.11,0,.19l-.03.33v.3c.01.26.01.47,0,.62v.03s0-.03,0-.03l-.09-.73v-.23c0-.06-.01-.13-.03-.19,0-.07,0-.14-.05-.22l-.05-.22v-.03s0,.03,0,.03l-.03.33-.03-.29s.02-.01,0-.03v.03c0,.07,0,.14,0,.23s-.02.18-.04.27c0,.02,0,.03-.03.04-.02,0-.03,0-.03,0v-.03c0-.07,0-.14,0-.23s0-.15-.01-.19v-.82s-.01-.3-.01-.3c0,0,0-.02-.01-.06.01-.05,0-.06-.04-.06v-.06s0-.26,0-.26c0-.04-.02-.06-.05-.06v.03s0,.1.01.16l-.04.14s0,.03-.02.04v-.03s-.01-.33-.01-.33v-.06s-.04.04-.04.04c0,.02,0,.03-.02.04l.02.09-.02-.09-.02-1.14v-.23s0-.03,0-.03c0,0-.01,0-.03,0,0,0,0,.01,0,.03v.49s-.02.02-.02.04v-.03s-.01-.03-.01-.03l-.02-.09s-.02.06-.01.1l-.04.27s-.01,0-.03,0c0,0,0,.01,0,.03v-.06s-.02-.16-.02-.16v-.33s-.01-.03-.01-.03l-.02.07v-.06s-.03-.52-.03-.52c-.03-.54-.05-.98-.06-1.33l-.1-1.35-.04-.48c-.01-.06-.04-.09-.08-.08-.18.08-.47.19-.88.32-.13.03-.29.08-.49.17l-1.26.4c-.37.12-.64.23-.82.31-.04,0-.09.05-.14.13-.21.24-.39.55-.55.94l-.1.12c-.11.2-.29.56-.55,1.07-.17.34-.28.58-.33.73-.02.03-.07.15-.15.36l-.02.07c.04.08.02.15-.05.21l-.06.18-.18.4s0,.07-.05.08c-.05.08-.07.11-.07.11-.09.17-.2.49-.32.95-.02.03-.03.11-.05.24l-.02.07v-.06s-.04-.13-.04-.13l.09-.64-.02-.09s-.03-.09,0-.16c.02,0,.03,0,.03,0,0-.02,0-.03,0-.03.02-.09.04-.23.04-.4.02-.03.01-.08,0-.16-.02-.08-.01-.15.02-.2l.34-.86.04-.14-.1.12s-.06.08-.07.15c-.03.07-.05.12-.07.15-.09.19-.17.33-.24.41l-.04.14-.04.11s-.06.02-.06.04l-.04-.02c.03-.05.05-.08.05-.08.02,0,.03,0,.03,0,0-.02,0-.03,0-.03-.01-.06.02-.18.09-.35.06-.14.08-.24.07-.28.01-.13.02-.2.02-.2.02,0,.03,0,.03,0-.03-.02-.04-.02-.04-.02-.02,0-.03.02-.03.04-.03.14-.1.31-.19.5l-.02.07c-.01.13-.04.24-.06.31-.03.07-.09.23-.19.47,0,.02,0,.03,0,.03-.02,0-.03,0-.03,0v-.03s.03-.14.03-.14c-.04-.17,0-.36.1-.58.09-.19.14-.35.16-.46,0-.11.02-.19.08-.25h.03s-.03-.08.01-.11c.02-.03.03-.05.05-.08v-.13c.04-.05.05-.09.05-.11v-.03s-.04,0-.04,0l-.07.11c-.02.11-.07.19-.15.23-.04,0-.07.07-.09.18l-.06.04.02-.07c0-.07.04-.17.1-.32.07-.08.13-.27.17-.56l.02-.07.02-.07-.06.04c-.08.13-.27.5-.58,1.11l-.02.04v-.06s.28-.59.28-.59l.02-.2-.07-.02s-.05.03-.08.08c0,.02,0,.04.01.06-.02,0-.04.02-.06.04l-.03-.12c.03-.05.06-.12.08-.21.05-.08.04-.12-.03-.12h-.03s-.06.05-.06.05l.02-.07c.02-.09.05-.16.08-.21l.1-.32.16-.3.28-.52.18-.37.07-.15v-.06c-.08,0-.11-.02-.09-.05.02-.03.03-.05.05-.08l.02-.04.03-.04v.06s.02.03.02.03h.03s.03-.06.05-.08c.04-.03.08-.06.11-.09l.03-.14v-.03s-.08-.02-.08-.02c0,.02-.01.05-.05.08v.13s-.03,0-.07.01v-.03c.07-.17.11-.27.13-.29.01-.05.03-.09.07-.15.03-.05.06-.1.07-.15.04-.03.07-.09.09-.18.05-.16.08-.27.09-.32l-.04-.02s-.01,0-.03,0c0,0,0-.01,0-.03v-.06s.04-.04.04-.04l.1-.32.15-.2.47-1.02.24-.41.26-.48.02-.04v-.06s-.04.02-.04.04l-.25.48-.13.16s0,.03-.03.04v-.06s.07-.21.07-.21c0-.02,0-.03,0-.03.02-.03.01-.05-.01-.06v-.03c.04-.1.07-.19.1-.28.04-.12.08-.23.13-.32.23-.44.35-.66.35-.66l.19-.47c.09-.28.2-.52.33-.73l.31-.82c.04-.1.1-.21.16-.33.06-.12.12-.28.19-.47l.32-.79c.14-.36.22-.56.23-.61.07-.1.12-.22.15-.36.08-.24.15-.4.22-.51.04-.1.09-.22.15-.36.06-.14.11-.31.15-.49.02-.11.08-.25.18-.4.1-.15.17-.27.22-.34l.1-.12c.03-.05.09-.09.17-.1.08-.02.14-.04.18-.07.16-.08.26-.12.3-.13.08-.02.19-.02.33,0,.05.01.12,0,.23-.02.04,0,.09-.02.16-.03.06-.01.11-.01.13,0,.03.02.06.02.1.01.07,0,.15,0,.26,0,.13,0,.24,0,.33.03.08.05.21.1.39.14l.24.05.12.1c.09,0,.15.02.18.06.05.01.08.02.1.01l.11.04.29.3v.06s-.09.12-.09.12c-.07.1-.1.21-.1.32.04.17.06.31.06.44,0,.13,0,.24,0,.33l.07.64.06.87.04.65c.05.43.08.77.09,1.03,0,.11,0,.23.01.36,0,.11,0,.22,0,.33.01.06.02.13.01.19-.01.05-.01.1,0,.16l-.02.2c-.04.14-.06.22-.08.25l-.02.07c-.04.14-.02.37.06.71,0,.02.03.03.07.02l.09-.02-.09.05s0,.03-.02.04c-.02,0-.03.02-.02.04,0,.04.02.06.04.06.04-.03.06-.04.06-.04h.03s0,.02,0,.02l-.03.04.07.02s.1-.05.18-.07h.06s-.03,0-.03.02l-.15.07-.03.04h.03s.38-.06.38-.06l.16-.03s.04,0,.06-.01c.04,0,.08,0,.1.01s.08.02.16,0l.4-.12h.06s-.06.03-.06.03c-.12.07-.22.11-.3.13-.02,0-.03.02-.03.04h.03s.16-.04.16-.04l.04.02h-.03s-.09.06-.15.07l-.51.21s0,.01,0,.03c0,0-.01,0-.03,0h.03s.65-.18.65-.18c.12-.03.22-.06.27-.09l.07.02h-.06s-.36.16-.36.16c-.02,0-.09.05-.2.14-.12.07-.23.11-.33.14-.04.03-.1.05-.18.07v.03s.23-.02.23-.02c.02,0,.03-.02.03-.04.03-.05.07-.07.12-.06.04,0,.07-.02.09-.02.02,0,.03,0,.04.02h-.03s0,.04-.03.04h.03s.03,0,.04.02v.03s.04,0,.04,0c0-.02,0-.03,0-.03l.06-.04.49-.17c.12-.03.22-.06.28-.09l.04.02h-.03s0,.04-.03.04h.03s.46-.14.46-.14l.23-.02s-.03.02-.02.04c-.09,0-.16.01-.22.05-.04,0-.07.02-.09.02-.06.03-.16.07-.31.1-.06.01-.11.05-.14.1h-.03s-.06.02-.06.02c-.06.01-.11.04-.15.07-.04.03-.08.05-.12.06l-.06.04s.03,0,.04.02c.02,0,.03,0,.04.02h-.03s-.03.01-.03.01h-.06s.02.11.02.11h.06s.24-.13.24-.13c.05.01.1,0,.16-.03.06-.03.1-.05.12-.06.02,0,.03,0,.03,0h.06s-.01.02-.06.03c-.16.08-.3.13-.42.16l-.08.08s-.03.02-.02.04h.03s.41-.1.41-.1h.1s.03,0,.03,0l.4-.12c.17-.04.28-.07.34-.11l.28-.09.42-.16h.06s.07,0,.07,0h-.06s-.48.22-.48.22l-.3.13-.06.04h.06s.18-.09.18-.09c.19-.04.42-.11.71-.22.1-.02.24-.07.39-.15l.49-.17c.12-.03.22-.06.27-.09.04,0,.04,0,0,.03,0,0,0,.01,0,.03,0,0,.01,0,.03,0,.02,0,.03-.02.03-.04l.68-.18.95-.3.25-.05h.03s-.03.01-.02.03l-.24.09-.6.26-.39.15c-.08.02-.15.04-.21.08-.26.1-.45.2-.56.29l-.6.26-.76.26-.63.27-.61.23-.51.21-1.14.48s-.08.06-.14.1c-.06.01-.11.04-.15.07-.04,0-.06.03-.05.08l.02.39v.46c.01.06,0,.12-.03.17,0,0,0,0-.03,0,0,0,0,.01,0,.03v-.03s-.02-.23-.02-.23l-.02-.23v-.1s-.02-.13-.02-.13l-.07.11v-.03s-.05-.06-.06-.12v-.03s-.03.04-.03.04v.19c.01.11.03.26.07.44-.02.03-.02.05-.02.07.02,0,.04-.02.06-.04.02,0,.02,0,0,.03l-.05.08c-.03.07-.04.16-.04.27.02.08.03.15.04.19.08.35.11.62.11.8l.03,1.04c0,.11,0,.35,0,.72.01.17.02.33,0,.49-.01.13-.02.26-.02.36.01.37,0,.69-.02.95-.03.27-.04.48-.03.63,0,.18,0,.31.02.39,0,.04.01.06.01.06.03.06.04.13.02.23l-.03.33-.07.44c.01.06.01.12,0,.16-.03.38-.04.58-.03.6-.02.03-.02.07,0,.13v.13c0,.24,0,.4-.03.5,0,.22.02.38.04.48l.04.65c.02.08.03.17.02.26,0,.09,0,.16.02.23,0,.04,0,.12-.01.23,0,.13.03.24.07.34v.03s-.05.02-.05.04c0,.04.02.07.02.09-.02.09-.03.17-.01.23h-.03s0-.02,0-.02ZM97.22,21.4l.04-.14v-.03s-.04.02-.03.04c-.03.05-.05.09-.04.11v.03s.04,0,.04,0ZM105.89,26.49s-.04-.02-.05-.09v-.13s.03,0,.03,0c.01.06.01.11,0,.13l.02.09ZM104.47,24.15s0-.03,0-.03c.02,0,.03,0,.03,0-.02-.08-.02-.17,0-.26v-.06s-.02-.03-.02-.03l-.02.04v.33s.01.03.01.03ZM104.75,24.25s.05-.03.08-.08c-.02,0-.03,0-.04-.02,0-.02,0-.03,0-.03-.04,0-.06.04-.04.11v.03ZM105.33,24.81c.03-.05.05-.08.05-.08l-.02-.09-.04.11v.06ZM104.79,23.98l.02-.07c-.01-.06-.01-.12,0-.16h.03s0,.02,0,.02c0-.02,0-.03,0-.03.02,0,.03,0,.03,0l-.08-.21v-.03s-.04.02-.03.04c-.01.13-.01.24,0,.33-.02.03-.02.07,0,.13,0,0,0,.02.01.06l.02-.07ZM104.5,23.26s-.02-.03-.04-.02v.03s0,.08,0,.16c-.01.05-.01.1,0,.16l.03-.33ZM105.37,23.92s.02-.07,0-.13h.03c-.02-.09-.04-.15-.07-.19v-.03s0,.03,0,.03v.33s.04,0,.04,0ZM104.82,23.35c.02-.09.03-.17.01-.23,0-.07,0-.12,0-.16l-.02-.09v-.03s-.04.02-.03.04v.03c-.04.08-.05.14-.01.2v.1c-.04.05-.05.11-.04.17l.04.06.05-.08ZM104.27,22.33s.02-.05.02-.07c-.01-.04,0-.08,0-.1v-.06s-.03.07-.03.07l-.02.07.02.09v.03s0-.03,0-.03ZM104.84,22.69v-.03c-.02-.06-.02-.12,0-.16l-.04-.02v.03s-.03.14-.03.14c-.04.03-.04.05-.02.07.03.02.04.03.04.06h.03s.02-.08.02-.08ZM104.82,22.3l.02-.07c-.02-.08-.02-.19,0-.33v-.03s-.01-.03-.01-.03h-.03s0,.46,0,.46l.04.02v-.03ZM104.25,21.67s.03-.02.02-.04v-.1s-.02-.13-.02-.13v-.06s-.03.07-.03.07c.02.1.03.18.02.23v.03ZM98.97,17.09s.06-.02.06-.04c.02-.03.02-.05.02-.07.04,0,.07-.03.09-.05.02-.03.02-.05.02-.07.01-.05.04-.1.1-.15.05-.06.09-.11.1-.15.03-.05.04-.11.03-.17.02-.03.02-.06.01-.1h.03s0,.03.01.06c.02,0,.03-.02.03-.04.04-.03.05-.08.03-.14,0-.07.02-.11.04-.14,0,0,0-.01,0-.03,0-.02-.02-.03-.04-.02-.02,0-.04.02-.06.04,0,.02,0,.01-.04-.02v.06s0,.08-.01.17c-.04.03-.06.07-.07.11-.01.05-.03.08-.04.11-.02,0-.03.03-.02.07.02,0,.03-.02.02-.04l.04.02s0,.07-.05.08c-.05-.01-.08,0-.12.06-.05.08-.07.11-.07.11.03.04.04.08.03.13-.01.05-.03.08-.04.11,0-.04-.03-.07-.05-.09l-.05.21h.03ZM104.51,21.32s0-.03,0-.03c.02,0,.03,0,.03,0-.02-.08-.02-.19,0-.33v-.06s-.07-.09-.07-.09v.1s0,.05-.02.1c0,.02.02.05.05.09v.19s.02.03.02.03ZM104.83,21.61v-.46s0-.03,0-.03v-.06s-.03.07-.03.07v.16s0,.33,0,.33v.03s.03-.04.03-.04ZM99.62,15.9s0-.08.01-.1v-.06s-.04.04-.04.04c-.03.05-.04.1-.03.14l.02.09.04-.11ZM104.79,20.84s0-.03,0-.03c.02-.03.02-.05.02-.07.01-.13.01-.23,0-.3.01-.13.01-.23,0-.3v-.03s0,.01,0,.03c0,0-.01,0-.03,0v.06s-.01.33-.01.33v.03s0-.03,0-.03v-.1s-.03-.06-.03-.06v.03s0,.1,0,.16c.01.04,0,.09-.03.14l.02.09s.03.03.07.02ZM99.75,15.58c.08-.04.11-.08.11-.12v-.03s-.02-.03-.04-.02c-.07.1-.1.15-.1.15v.03s.04,0,.04,0ZM104.31,20.12v-.13s-.03-.29-.03-.29v-.03s-.03.04-.03.04l.03.42v.03s.03-.04.03-.04ZM104.22,19.85c0-.18,0-.31-.02-.39v-.03s0,.03,0,.03l-.02.2v.16s0,.03,0,.03h.03ZM99.68,14.94v-.03c-.08.08-.12.14-.13.19v.03s.13-.19.13-.19ZM99.97,15.4v-.06s.02-.14.02-.14c0,0,0-.02-.01-.06l-.06.18v.06s0,.07,0,.07l.06-.04ZM104.28,19.54l.03-.04v-.06s-.03-.06-.03-.06c0,.02,0,.03-.03.04v.13s.04.06.04.06v-.06ZM104.13,19.31v-.06s-.03-.06-.03-.06c0-.02,0-.03,0-.03.02,0,.03,0,.03,0l-.04-.02s0,.01,0,.03c0,0,0,0-.03,0l.02.09v.06s.04,0,.04,0ZM104.44,19.67c-.01-.06-.01-.12,0-.16l.02-.04h.03s0-.04,0-.04l-.04-.02-.04-.02v.03s0,.23,0,.23v.03s.01.03.01.03l.02-.04ZM99.73,14.87l.07-.15v-.03s-.04,0-.04,0l-.07.15v.03s.04,0,.04,0ZM100.09,15.18s0-.06.04-.11l-.02-.09c-.05.08-.07.11-.07.11,0,.04.03.07.05.09ZM100.02,15s0,.03,0,.03c.02,0,.03-.02.02-.04l.1-.12-.04-.02s-.02-.02-.03,0l-.07.11v.03ZM101.98,16.8s.05-.04.09-.05h.06s.06-.06.06-.06h-.06s-.06.03-.06.03c-.06.01-.09.04-.08.08-.05-.01-.11,0-.19,0h-.06s.07.03.07.03l.19-.04ZM104.48,19.27s.03-.02.02-.04v-.03s-.01-.03-.01-.03l-.04-.06s0,.01-.03.04c0,0,0,.01-.02.04v.03s.04,0,.04,0l.02-.04v.03s.01.03.01.03v.03ZM104.77,19.53s.03,0,.03,0c0-.02,0-.03,0-.03.01-.05.01-.1,0-.16v-.03s-.03.04-.03.04v.13s.01.06.01.06ZM100.18,14.86c.03-.05.05-.09.04-.11l-.03-.13c-.03.05-.05.09-.04.11l.03.13ZM100.36,14.6s.03-.04.07-.11c-.07-.03-.11-.05-.11-.07-.03.05-.05.08-.05.08-.02.03-.02.05-.02.07,0,.02.02.04.04.06l.04.06.02-.07ZM104.76,19.2s0-.03.03-.04c.02,0,.03-.02.02-.04v-.26s-.03-.19-.03-.19l-.04-.02v.03c.03.1.03.18.02.23v.03c.02.06.01.13-.01.2v.06ZM104.46,18.55s-.02-.03-.04-.02l-.06.04.05.06.05-.08ZM100.45,14.44c.03-.05.05-.08.05-.08l-.04-.02s-.06.02-.06.04l.04.06ZM100.17,14.51l.08-.21.19-.3v-.03s-.04,0-.04,0l-.16.33-.12.22v.03s.03-.04.03-.04ZM100.52,14.3l.05-.08s.07-.1.08-.21l.06-.18.06-.18s.03-.02.03-.04h-.03s-.04.06-.08.09c-.04.03-.04.07,0,.13-.03.05-.06.08-.08.08-.02,0-.04.02-.06.04-.02.03-.02.05-.02.07.02.08,0,.13-.04.14-.02.03-.02.06-.01.1l.04.02ZM100.46,13.43l.05-.08s-.03,0-.04-.02l-.07.15v.03s.06-.08.06-.08ZM100.68,13.51l.09-.18v-.03s-.04,0-.04,0l-.05.21s-.08.04-.11.09c-.03.05-.04.1-.04.14h.03s.12-.23.12-.23ZM100.9,13.5l.05-.21v-.03s-.04,0-.04,0l-.09.18.03.12.05-.08ZM101.88,15.9s.03,0,.04.02c.02,0,.04-.02.06-.04l.7-.25.69-.15c.05-.06.08-.09.07-.11l-.02-.09-.1-.76-.06-.44c0-.07,0-.14-.02-.23l-.03-.13c-.03.05-.05.08-.05.08v.03s-.5.96-.5.96c-.07.1-.12.17-.15.2-.06.03-.12.1-.18.2l-.1.28c-.02.09-.05.16-.08.21-.07,0-.12.01-.15.07-.02.03-.04.05-.08.08,0,.04,0,.06-.02.07ZM101.16,13.01s.03,0,.03,0c0-.02,0-.03,0-.03.03-.05.05-.09.04-.11.03-.05.06-.12.08-.21v-.06s-.03-.06-.03-.06l-.02.07-.02.07s-.03.06-.04.11c0,.02-.01.04-.06.04v.03s.01.08,0,.1v.03s.01.03.01.03ZM103.89,15.2s.05-.06.05-.08l-.03-.16.02-.07s-.04.04-.09.05v.13s0,.06,0,.06l.05.06ZM103.75,15.14l.02-.5s-.02-.03-.04-.02v.03s0,.26,0,.26c.02.08.02.16.02.23v.03s0-.03,0-.03ZM101.37,12.51l.07-.15-.04-.06h-.03s0,.08-.03.18v.06s.04-.04.04-.04ZM104.01,15.14s.03-.03.02-.07c0-.09,0-.19-.04-.32v-.06s-.04.04-.04.04l.06.41.02.09-.02-.09ZM103.89,14.88l.04-.14-.05-.06-.02.07s-.05.07-.04.11v.03s.07-.01.07-.01ZM104.28,15.18s.06-.02.06-.04c.02,0,.02-.01,0-.03,0-.02,0-.03,0-.03-.05-.01-.06-.06-.03-.16,0-.02,0-.02.03,0h.03s-.02-.04-.04-.03c-.06-.05-.07-.11-.03-.16v-.06s-.05-.02-.05-.02v.03s-.01.06,0,.1c0,.02,0,.04-.02.07l.06.28v.06ZM104.28,14.1s-.01-.06-.01-.06c0-.02-.03-.03-.07-.02,0-.02-.01-.02-.03,0l.07.02.04.06v.06s0-.06,0-.06ZM105.01,14.76v-.13s-.01-.06-.01-.06c-.03.05-.05.08-.05.08,0,.02,0,.04-.02.07,0,.02.02.04.05.06,0,.04.02.06.04.06v-.06ZM103.8,13.58s.01-.04,0-.03v-.33s-.02,0-.04,0c0,0,0-.01,0-.03v.03c0,.07.01.16.04.29v.06ZM104.69,14.18l.02-.07s-.02-.03-.04-.02c0-.02,0-.04-.01-.06v.06s0,.06,0,.1l.05.06v-.06ZM106.22,13.84s0-.03,0-.03c.02,0,.03,0,.03,0,.03-.14.05-.23.04-.27l-.13-.59v-.03s0,.03,0,.03l.06.74v.13s0,.03,0,.03ZM109.05,14.96c.07-.06.13-.09.17-.1.02-.03.03-.03.03,0,.02,0,.04,0,.06-.01l.07.02h-.06c-.08.03-.14.06-.18.09l-.09.02ZM106.37,5.82c-.1.02-.25.01-.43-.04-.21-.04-.44-.16-.7-.34-.19-.16-.47-.3-.85-.44l-.64-.25c-.25-.12-.38-.18-.4-.18l-.79-.32-.73-.33-.69-.31c-.08-.05-.42-.17-1.03-.37l-.47-.19c-.05-.03-.17-.07-.35-.12-.23-.04-.39-.08-.49-.12-.19-.07-.35-.14-.47-.22l-.32-.13c-.16-.14-.27-.26-.34-.35-.02-.02-.04-.05-.05-.09-.01-.06-.02-.1-.03-.13.1-.02.17-.08.19-.17,0,.07.01.12.06.15.05.01.07.02.07.02l.06-.04v.06c.08,0,.11-.03.09-.11.05.01.08.04.11.07.05.03.1.04.14.04-.06-.05-.12-.09-.19-.12l.02-.04c.15.1.28.14.39.11l-.29-.13s.02-.03.05-.08c0-.04-.03-.06-.08-.05l-.19.04c-.03.07-.05.11-.07.11-.03-.02-.06-.04-.11-.07.11,0,.17-.06.19-.17-.06.01-.12.01-.16,0v.13s-.04,0-.04,0l-.05-.09h-.03s.02.1.02.1c-.03.05-.06.08-.08.08-.03-.02-.04-.03-.04-.06,0-.02-.02-.03-.04-.02-.05-.01-.07,0-.06.04.03.04.03.06.01.06v-.03s-.06-.11-.09-.21l.05-.08s.05-.03.08-.08l.28.07.03-.14s-.03-.07-.05-.09c-.03-.04-.06-.05-.08-.05-.02,0-.07.02-.16.03-.06.01-.11.05-.14.1-.01-.06-.01-.12,0-.16-.02,0-.06,0-.11-.04l.2-.3-.07-.02s.05-.04.09-.05l.07-.11.06-.04c.11-.11.15-.21.13-.29,0-.07.05-.13.12-.19.04-.03.09-.05.15-.07.17-.04.31-.01.44.07,0,.02,0,.03,0,.03.02,0,.03,0,.03,0,.13.01.27.05.42.11.16.05.29.09.39.11.26.08.61.24,1.06.49l.47.19.4.18.18.09.42.14c.07.03.14.06.21.08.09,0,.18.03.28.07l.57.2c.24.08.41.15.54.21l.76.33c.19.09.49.24.89.46l.47.19c.1.07.25.14.44.23.25.12.62.26,1.14.41l.39.14c.18.11.28.2.32.26.03.04.06.08.1.14.03.04.05.1.07.18v.03s0,.13-.06.28c-.1.13-.24.27-.4.41-.15.12-.26.21-.33.27-.11.09-.28.2-.51.34l-.33.14-.09.02ZM98.39,2.09c-.09-.13-.19-.17-.28-.1l.28.1ZM99.78,2.8l-.28-.1.29.13v-.03ZM99.11,2.26h-.06s-.03.02-.03.02v-.06s-.36-.09-.36-.09v.03c.08.05.21.1.4.14,0,.02.03.03.07.02v-.06ZM100.19,3.01s0-.03.02-.04c-.14-.04-.26-.09-.36-.15v.03c.08.05.19.1.34.16ZM99.18,2.28c.01.06.07.12.17.16.12.04.2.04.23.01l-.4-.18ZM99.81,2.6s.03-.02.03-.04c-.02,0-.06,0-.1-.01-.03-.04-.07-.04-.13,0l.21.05ZM99.03,2.05c-.05-.03-.12-.06-.21-.08.05.03.12.06.21.08ZM100.2,2.74l-.14-.04v.03s.15.07.15.07v-.06ZM98.31,1.45s-.09-.01-.13,0c-.04,0-.07.04-.08.08l.09-.02s.03.02.08.05l.04-.11ZM98.22,1.18v.06c.03.08.11.13.24.15l-.24-.21ZM101.46,3.26c-.05-.03-.12-.06-.21-.08.06.07.13.1.21.08ZM100.1,2.27l-.61-.26v.03s.59.27.59.27l.03-.04ZM98.78,1.35s0-.03,0-.03c.02,0,.03,0,.03,0l-.11-.07s-.07,0-.1-.01c-.03-.04-.04-.08-.03-.13.08.05.21.1.39.14,0,.02.03.03.07.02v-.03s-.03-.03-.08-.02l-.11-.07s-.06-.02-.04-.02c.04-.03.05-.06.05-.08l.02-.07c-.1.02-.17.05-.21.08-.06.01-.11.01-.13,0h-.06s-.04.15-.04.15h-.03s.39.15.39.15ZM100.04,1.73c-.09-.02-.16-.05-.21-.08-.05-.03-.1-.05-.15-.07l-.16.03-.02-.09-.25-.08h-.06c.14.07.25.12.33.17.04,0,.08,0,.1.01l.07.02c.1.07.18.1.22.12l.14.04v-.06ZM99.66,1.48c-.06-.05-.15-.1-.29-.13-.14-.06-.24-.07-.3-.03l.59.17ZM101.32,2.5l-.5-.22c-.14-.06-.25-.09-.32-.1.39.18.68.3.87.37l-.05-.06ZM100.45,1.97c-.06-.07-.12-.1-.18-.09v-.06s-.04,0-.04,0c0,.02,0,.04-.02.07,0,0,.01,0,.04.02.03.06.1.08.21.05ZM100.7,2.04l-.15-.07s0,.01,0,.03c0,0-.01,0-.03,0,0,.02.06.04.18.06v-.03ZM100.19,1.66l-.25-.08c-.05-.03-.09-.05-.11-.04l-.11-.04c.06.05.16.12.31.2.17.07.3.11.38.11l-.23-.15ZM99.08.92l-.09.02h-.03s.15.07.15.07l-.02-.09ZM101.36,2.36c-.06-.05-.11-.07-.18-.06v.03s.18.06.18.06v-.03ZM100.9,2.03c-.13-.08-.22-.13-.29-.13,0,0,0,.01,0,.03,0,0-.01,0-.03,0l.32.13v-.03ZM102.25,2.82c-.07,0-.17-.04-.32-.1v.03c.06.03.11.05.15.07.05.01.09.02.14.04l.02-.04ZM101.29,2.21c-.03-.06-.08-.07-.14-.04.05.03.1.04.14.04ZM101.55,2.32s-.05-.03-.15-.1l-.02.04c.1.07.15.1.15.1l.02-.04ZM102.87,3.11s0-.03,0-.03c.02,0,.03,0,.03,0l-.28-.1v.03s.26.11.26.11ZM102.29,2.75s.03,0,.03,0c0-.02-.02-.03-.04-.02l-.15-.07.12.1h.03ZM102.43,2.62l-.82-.31s-.03.02-.03.04c.13.08.27.15.44.2s.29.09.38.11l.02-.04ZM102.79,2.9c-.05-.03-.1-.04-.14-.04-.03-.02-.05-.01-.06.01.02,0,.05.01.08.05.05.01.09,0,.12-.03ZM102.69,2.76c-.1-.07-.18-.09-.25-.08.05.03.12.06.22.08h.03ZM103.83,3.2c-.17-.09-.34-.17-.5-.22-.14-.06-.29-.11-.43-.17-.02,0-.03.02-.03.04.55.21.86.33.93.35h.03ZM103.39,3.1l-.24-.05c.1.07.18.09.25.08v-.03ZM104.19,3.32c-.07,0-.12-.02-.17-.03-.02-.02-.05-.03-.08-.05.11.09.19.11.25.08ZM6.17,71.59c-.14-.06-.25-.06-.33-.03-.06.03-.11.05-.16.03-.04,0-.08.02-.13.03-.13.03-.22.01-.27-.04-.02,0-.05-.01-.08-.05-.05-.01-.09,0-.13.03-.05-.03-.11-.06-.18-.09-.09,0-.15-.02-.18-.06,0-.02,0-.03,0-.03-.02,0-.03,0-.03,0-.13,0-.26-.05-.4-.18l-.24-.21-.27-.2-.03-.13s.05.01.06-.01c0,0,0,.01,0,.03l.27.04h.03s0-.02,0-.04c0,0-.01,0-.03,0l-.32-.1v-.03s.05-.02.05-.04c0-.02-.02-.03-.04-.02-.05-.03-.06-.07-.03-.13.01-.05.02-.08.01-.1l.02-.04s.05-.01.09-.02c.04,0,.08,0,.11.04,0,.02.02.03.04.02v-.03c-.06-.03-.09-.05-.11-.04-.02,0-.04,0-.06.01-.03-.02-.03-.05-.02-.09v-.03c-.05-.01-.08-.05-.1-.11s-.01-.11,0-.13c.04,0,.06-.02.06-.04,0-.04-.02-.08-.03-.12-.03-.06-.05-.11-.03-.16v-.59s.02-.17.07-.44l.05-.53.13-.62.16-.79.12-.49c0-.07.01-.13.02-.2,0-.09.02-.18.04-.27l.07-.15.13-.59.06-.31c-.02-.17,0-.36.07-.57.04-.21.07-.37.09-.48l.05-.21c.04-.23.08-.4.12-.52.05-.29.1-.55.16-.76.04-.12.06-.24.05-.37,0-.22.02-.41.07-.57.04-.1.08-.23.11-.38.03-.16.06-.29.08-.38l.1-.45c.04-.23.08-.4.12-.52.05-.18.09-.33.14-.42v-.03s.08-.35.08-.35l.08-.25c0-.09.03-.2.09-.35.02-.09.04-.18.04-.27.02-.09.06-.2.1-.32.08-.24.13-.41.15-.52.17-.61.29-1.06.36-1.36.13-.42.21-.74.25-.97.08-.24.13-.42.14-.55.06-.23.07-.44.03-.63-.01-.06-.01-.16,0-.3,0-.11.05-.24.14-.39l.2-.44c.04-.1.14-.23.28-.39.08-.13.27-.25.58-.35.17-.04.29-.05.38-.05.05.01.09.01.13,0,.06-.03.11-.05.16-.03.41-.04.73.01.99.18l.31.23.15.07.04.06s-.01.2.02.52v.19s.01.16.01.16c.03.12.14.18.33.16.08-.02.15-.01.2.02v.03s-.02,0-.02,0l-.19.04c-.07.06-.12.11-.13.16l-.14.39s0,.01,0,.03c0,0-.01,0-.03,0-.09.09-.1.19-.03.3v.1s-.02.06-.05.11c.01.06.01.1-.01.1-.02.03-.04.03-.06.01-.03-.02-.05-.02-.07-.02-.06.01-.11.05-.14.1l-.19.5c-.08.24-.12.42-.11.55.05.21,0,.47-.12.78l-.23.77-.16.46-.04.11s0,.08-.03.17c-.01.05-.03.12-.05.21-.03.07-.05.15-.08.25-.04.23-.08.4-.12.52-.04.12-.08.26-.11.42,0,.15-.02.28-.02.36l-.07.57h.03s.11-.26.11-.26c.13-.29.2-.44.2-.44.13-.2.39-.37.78-.5.17-.04.29-.07.37-.11h.03s.1,0,.1,0c-.02.03-.05.04-.09.05l-.48.2c-.28.11-.49.27-.61.49-.1.15-.16.32-.19.5-.06.34-.15.6-.29.78l-.27.42c-.1.15-.19.37-.28.65-.08.24-.13.42-.14.55-.09.37-.15.64-.18.83-.02.09-.06.2-.1.32-.02.09-.05.21-.09.35-.03.07-.05.16-.07.28-.02.11-.04.2-.08.25-.06.14-.11.37-.18.69,0,0-.02.03-.05.08,0,.04,0,.09-.04.14l-.07.44-.08.54-.06.18-.04.14s.03.07.05.09c0-.02,0-.03.02-.04.02,0,.03-.02.02-.04l.15-.36s.02-.03.05-.08l.02.09-.19.63-.15.69c0,.07,0,.12.03.16.03.02.07,0,.12-.03.06-.01.12-.04.18-.07.06-.03.12-.06.18-.07.1-.04.22-.1.35-.18.13-.09.25-.16.35-.21l.28-.22.13-.16.06-.04c.12-.03.19-.07.2-.14,0-.02,0-.03,0-.03.02,0,.03,0,.03,0v.03s-.08.18-.08.18c-.03.05-.03.07.01.06.02,0,.04.01.04.06.03.02.05.01.06-.01l.32-.2h.03s.04-.02.06-.02c.02-.03,0-.06-.02-.09l.02-.07.06-.04c.06-.01.09,0,.07.02l.04.02.02-.04s-.02-.07.04-.11l.23-.15.12-.03s.01,0,.04.02c.04,0,.06-.03.05-.08l.02-.04s.06.02.1.01c.04-.03.07-.04.09-.02l.06-.04c.05-.08.07-.11.07-.11.02-.03.03-.04.06-.04.04,0,.07-.03.09-.05.05.01.09,0,.12-.06.03-.05.06-.08.08-.08.04,0,.08-.04.11-.09l.14.04-.02.04c-.07,0-.11.05-.13.16-.02,0-.03.02-.02.04.02,0,.03,0,.03,0h.06c.03-.09.07-.12.11-.1l.06-.04s.03-.05.05-.08c.04-.03.08-.06.14-.1.02,0,.03,0,.04.02l.04.02s.05-.03.09-.02c.04,0,.07-.04.08-.08l.06-.04c.14-.05.27-.11.39-.18.12-.07.21-.12.29-.16l.17-.1s.04-.03.06-.01c.04,0,.08,0,.11.04l.04.06.04.02v.1s-.3.32-.3.32l-.07.15s0,.06.04.06l.04.02s0,.01,0,.03c0,0-.01,0-.03,0l-.27.26c-.15.12-.26.22-.33.3-.06.03-.12.1-.18.2v.03s.04,0,.04,0l.25-.19h.03s-.07.05-.11.08c-.04.03-.07.07-.1.12,0,0-.03.05-.1.15l-.07.11-.11.09v.06s.08-.01.08-.01l.23-.15.27-.12c.19-.13.35-.22.47-.27,0,.04,0,.08-.01.1,0,0-.01,0-.03,0t0,0h-.03c.05.04.04.06-.02.08h-.03s-.09.06-.09.06l.05.09s0,.03,0,.03c.02,0,.03,0,.03,0l.39-.18h.03s.06-.05.06-.05l-.02.07v.06s.21,0,.21,0c.04-.03.06-.06.08-.08.04-.03.09-.05.15-.07.08-.02.14-.04.18-.07h.03s0,.02,0,.02h-.03s-.05.08-.05.08h.16s.22-.05.22-.05c.02,0,.03,0,.04.02.1.07.15.1.15.1v.03s-.02,0-.02,0c0-.02-.02-.03-.04-.02-.05-.03-.09-.03-.13,0-.04.03-.07.05-.09.05l-.02.07h.06c.06-.03.12,0,.18.08,0,0,0,.01,0,.03.02,0,.04-.02.06-.04l.16-.03s0-.02,0,0c.02,0,.03,0,.03,0h-.03c-.07.07-.12.14-.15.24l-.06.04c-.16.08-.27.12-.33.14-.19.04-.33.1-.42.19-.09.09-.16.12-.21.11l-.12.06-.79.57-.27.26-.53.41-.24.25-.3.26c-.05.06-.11.1-.17.13-.06.03-.11.07-.14.1l-.11.09-.21.37s-.02.08,0,.16l.04.06-.02.07s-.02-.03-.04-.02c-.03-.06-.08-.08-.15-.07l-.07-.02c-.18-.11-.27-.17-.27-.17l-.18-.06-.06.04-.27.26-.09.05-.3.29-.04.11c-.03.05-.06.07-.09.05,0-.02-.03-.03-.07-.02-.11.09-.18.15-.19.17-.02.03-.04.05-.08.08-.04.03-.07.08-.1.15.01.06-.01.1-.07.11-.16.08-.3.1-.41.06-.03-.02-.06-.02-.1-.01-.1.02-.27.01-.5-.02v-.03c-.06-.03-.11-.03-.17,0-.04.03-.07.05-.09.05-.05.06-.14.12-.25.19-.14.07-.24.1-.31.07ZM4.35,70.12h-.03s-.07-.01-.07-.01c0,.02-.01.04-.06.04l.07.02h.06s.02-.05.02-.05ZM4,69.87c.06-.01.1-.03.12-.06h.03s-.03,0-.03,0c-.05-.01-.12,0-.23.02h-.06s0,.02,0,.04c0,0,.01,0,.03,0l.04.02.09-.02ZM3.83,69.12c-.01-.06-.01-.11,0-.13l.04-.27v-.06s-.04.04-.04.04l-.07.44.04.02.02-.04ZM4.28,69.38l-.05-.09s-.03,0-.03,0c0-.02,0-.03,0-.03l.02-.04s0,.01,0,.03c0,0,.01,0,.03,0v.03s.04,0,.04,0c0-.02,0-.03,0-.03v-.26s.02-.11,0-.19c.03-.05.03-.08-.02-.09v-.03s-.05-.06-.05-.06c0,0-.02.03-.05.08.02.1.02.19,0,.26l.04.02h.03s.04.02.04.02l-.02.07c-.07,0-.09,0-.06.01,0,.02,0,.04.01.06h.03s-.03,0-.03,0h-.03s0,.06-.01.11c-.03.05-.02.09.03.13,0,.04.02.06.04.06,0,.02.02.03.04.02l.02-.07ZM5.2,69.83c.08-.02.14-.04.18-.07v-.03s-.04,0-.04,0l-.09.05v-.03s-.06.04-.06.04c-.02,0-.03.02-.02.04h.03ZM5.52,69.5s.03,0,.03,0c0-.02,0-.03,0-.03h-.03c-.06.02-.11.04-.15.07v.03s.16-.07.16-.07ZM4.67,68.9s0-.03.02-.04c-.03-.02-.04-.05-.05-.09l-.02.07s.02.06.04.06ZM3.92,68.31v-.13s-.03,0-.03,0v.1s0,.06,0,.06l.02-.04ZM4.36,68.25s.02-.03.05-.08l-.07-.02v-.03s-.04-.02-.04-.02h-.03s.02.1.02.1c0,0,.03.02.08.05ZM5.8,69.57l.72-.32.15-.07.02-.04h-.06s-.6.24-.6.24l-.09.05-.02.04h-.06c-.08.03-.16.07-.24.13-.02,0-.03.02-.02.04h.03s.18-.08.18-.08ZM6.37,69.48s.07-.03.09-.05h-.1s-.05.03-.09.04c.03.02.06.02.1.01ZM6.45,69.1h.03s-.04-.03-.04-.03c-.2.09-.34.16-.41.22h-.03s0,.02,0,.04c0,0,.01,0,.03,0l.41-.22ZM4.41,68.01s-.02-.04.02-.07l.02-.07s-.02-.09.03-.17c0-.02,0-.03.02-.04,0-.02,0-.03,0-.03-.02,0-.03,0-.03,0,0,0-.02,0-.06.01l.02-.07.02-.07s0-.03,0-.03c-.02,0-.03,0-.03,0l-.06.04c.01.06,0,.14-.01.23l.04.02h-.03s-.03.07-.04.11c-.01.05-.02.08-.01.1v.06s.11.01.11.01l.02-.07ZM6.02,69.23c.19-.11.32-.18.38-.21h.03s-.03,0-.03,0l-.42.19v.03s.04,0,.04,0ZM4.04,67.53c.02-.09.03-.16.02-.2v-.03s-.06.21-.06.21l.04.02ZM6.72,69.27c.09.02.15,0,.18-.07.02-.03.06-.04.12-.06l.12-.06s.01,0,.03,0c.04,0,.06-.03.05-.08h.03c.08-.02.13-.05.15-.07l.02-.04-.07-.02s-.05.04-.09.05c-.06.01-.11.07-.13.16h-.19s-.23.16-.23.16v.03ZM4.47,67.4s.06-.02.06-.04c.02-.03.04-.07.07-.15,0-.07,0-.13-.04-.19-.03-.02-.02-.05.01-.1,0-.02,0-.03.02-.04.02-.03,0-.04-.04-.06v-.03s-.06.04-.06.04l-.04.27v.06s.02-.03.04-.04l.02-.04v.03c-.06.1-.09.15-.09.15v.1s.06.02.06.02ZM4.94,67.27s-.03,0-.03,0c0-.02,0-.03,0-.03v.03s-.06.03-.08.05v.03s.04.02.04.02l.07-.11ZM7.54,68.83s.07-.03.09-.05v-.03s-.1.02-.1.02v.03s-.09.02-.09.02c.03.02.06.02.1.01ZM4.61,66.65h.03s0-.04,0-.04c-.03-.04-.03-.06-.01-.06.02-.03.03-.04.06-.04,0-.02,0-.06.04-.11,0-.02,0-.04-.01-.06-.03-.02-.04-.02-.04-.02-.04,0-.06.03-.05.08l-.08.21.02.09.06-.04ZM5.91,67.55l.05-.24-.04-.02s-.01,0-.03,0c0,0,0,.01,0,.03l-.05.24v.06s.06-.08.06-.08ZM7.32,68.42s-.03,0-.03,0c0-.02,0-.03,0-.03-.02,0-.04.02-.06.04,0,0-.01,0-.03,0,0,.02.03.03.07.02l.06-.04ZM5,66.67s.02.03.04.02c0-.02,0-.03,0-.03l-.05-.09s-.03.02-.02.04c0,.04.02.06.04.06ZM10.2,70.51s0-.03,0-.03c0-.02,0-.06.04-.11.03.02.03.03,0,.03,0,.02,0,.06-.04.11ZM7.6,68.39s.03,0,.03,0c0-.02,0-.03,0-.03h-.03s-.1.05-.17.11h.03s.15-.07.15-.07ZM7.52,68.31s.07-.03.09-.05c0-.02-.03-.03-.07-.02,0,0-.02.03-.05.08,0,0,0,.01,0,.03.02,0,.03-.02.02-.04ZM4.75,66.26l.02-.2-.02-.09s0-.03,0-.03c-.02,0-.03,0-.03,0-.02,0-.03.02-.02.04v.03s.02.06.02.06c-.06.01-.08.06-.07.15-.02.03-.01.05.01.06,0,0,.01,0,.03,0h.06ZM5.02,66.43s0-.03.02-.04c0-.02,0-.03.02-.04v.03s.01.03.01.03h.03s-.02-.1-.02-.1v-.03s-.07.02-.06.04l-.02.04v.06ZM7.72,68.3c.08-.02.16-.06.24-.12h.03s-.02-.04-.04-.03l-.23.15ZM9.87,69.77s.1-.04.17-.1l.02-.04h-.03s-.21.09-.21.09c0,.02,0,.03-.02.04l.07.02ZM4.8,65.76s0-.03.02-.04c0-.02,0-.03.02-.04l.04-.11s-.03-.04-.01-.06c.02-.03.02-.04.02-.04.01-.13.04-.23.07-.28l.05-.21v-.06s-.07-.03-.11.02c0,.02,0,.08-.03.17l-.06.18-.05.24c-.02.09-.03.15-.03.17-.02.03-.02.05-.02.07,0,.02,0,.04-.02.07,0,.02,0,.03,0,.03-.02,0-.03,0-.03,0l.07.02.04-.14ZM7.97,67.49h-.03s-.05.04-.08.09v.03s.11-.12.11-.12ZM5,64.86s.03,0,.03,0c.02-.03.03-.05.05-.08l-.08-.05-.07.11.07.02ZM8.51,67.15s-.1,0-.16.03c-.04,0-.07.03-.09.05l-.02.07h.06s.2-.16.2-.16ZM5.08,64.46l.04.02s0-.03,0-.03c.02,0,.03,0,.03,0v-.03s-.1.02-.1.02l-.02.07.06-.04ZM8.78,67.02s.01-.04.06-.04h-.1s-.06.03-.06.03l-.02.04h.03s.09-.03.09-.03ZM9.15,67.24l.08-.08s-.05.04-.09.05l-.06.04h-.03s.03,0,.03,0h.06ZM5.19,64.2s0-.04.02-.07c.02-.03.01-.05-.01-.06l.02-.04.04-.14s-.02-.06-.04-.06l-.02.07-.02.07-.04.14s0,.04-.02.07l-.02.07s0,.01,0,.03c.02,0,.03-.02.02-.04l.06-.04ZM10.24,67.26s.03-.02.02-.04c-.02,0-.05,0-.1-.01-.05-.01-.08,0-.09.02-.02,0-.07.04-.14.1l-.02.04h.03s.06-.02.06-.02h.03c.01.06.03.07.04.05.02-.03.03-.04.06-.04l.11-.09ZM5.32,63.62s0-.06.04-.11l-.04-.06-.04.11.04.06ZM10.24,67.56c.15-.03.26-.07.34-.11.12-.07.24-.15.37-.24.04,0,.06-.02.06-.04h-.06s-.06.03-.06.03l-.15.07c-.13,0-.22.05-.27.12l-.23.15s-.03.02-.02.04h.03ZM9.84,66.3v-.03s-.07.01-.07.01l-.09.05-.02.04.07.02.11-.09ZM10.12,66.57c.08-.04.19-.12.34-.24l.02-.04h-.06s-.06.03-.06.03l-.04-.02v.03s0,.07-.04.08c-.03-.02-.04-.02-.04-.02l-.04-.02s.02.06.04.06c0,0,0,.01,0,.03,0,0,.01,0,.03,0h-.06s-.05.06-.09.07c-.02,0-.04.02-.06.04l-.02.04h.06ZM10.91,65.54s0-.03.02-.04l.24-.12.37-.28h.03s.07.01.07.01l-.02.04c-.05.06-.14.12-.25.19-.12.07-.18.11-.21.11l-.06.04c-.06.01-.08.04-.05.08l-.14-.04ZM11.97,64.36l.04-.14s.06-.04.12-.06v.03c-.03.05,0,.08.06.09h.03s-.03,0-.03,0l-.21.08ZM13.13,64.31s-.03,0-.03,0c0-.02,0-.03,0-.03-.17-.07-.27-.13-.3-.16-.03-.04-.07-.06-.11-.07-.03-.02-.05-.02-.07-.02h-.23s-.12.04-.12.04h-.03s.03,0,.03,0l.11-.09h.13s.03,0,.04.03c.02,0,.03-.02.02-.04.02-.03.04-.03.06-.01l.07.02c.23.15.36.25.39.31.02,0,.03,0,.04.02ZM16,57.53s0-.01,0-.03c-.01-.06-.01-.11,0-.13-.02-.08-.02-.14,0-.16.04-.12,0-.21-.09-.27-.06-.05-.07-.11-.03-.16l.02-.04.09-.02s.07-.04.08-.08c.03-.07.05-.12.07-.15.01-.05,0-.1-.03-.16-.01-.06-.03-.1-.06-.12-.02,0-.04,0-.06.01,0-.02-.01-.02-.03,0-.04,0-.04.03.01.06l-.02.07s0,.03-.02.04c-.02,0-.05.02-.09.05-.02.03-.02.07,0,.13h-.03s-.04-.05-.04-.05c-.01-.06-.01-.11,0-.13.1-.15.14-.26.13-.32-.02-.08-.02-.14,0-.16,0-.07.03-.22.06-.47l.05-.21c-.1.02-.16.1-.18.24-.02.09-.03.17-.01.23l-.07.15h-.03s-.02-.02-.04-.02c0-.02,0-.04.02-.07,0-.22,0-.38.02-.5l.02-.07s-.02-.03-.04-.02c0,.04,0,.08-.01.1l-.14.26-.04.11s0-.08.03-.17l.05-.37.02-.07s-.01,0-.03,0c0-.02,0-.03.02-.04.02-.03.02-.05.02-.07,0-.04-.02-.07-.02-.09l-.02-.26c0-.07.02-.11.04-.14.01-.05.03-.08.04-.11l.23-.77.07-.15c-.11.22-.19.42-.26.61-.05.16-.1.31-.14.42-.01-.06-.01-.11,0-.13.05-.19.07-.32.07-.41.01-.13.03-.25.06-.34.02-.09.05-.18.07-.28v-.36s-.01-.11,0-.2c.07-.28.11-.45.12-.52,0-.07.01-.13.02-.2,0-.07.02-.14.05-.21.06-.34.18-.66.38-.97l.23-.61.21-.41c.11-.2.21-.46.29-.78l.02-.36c.01-.13.06-.21.15-.23l.38-.08.44-.1s.05.08.12.1c.07,0,.09-.02.08-.08,0-.02,0-.03,0-.03.02,0,.03,0,.04.02l.5.19c.09.02.16.05.21.08.05.03.1.05.15.07l.08.08s.04.05.05.09c.03.02.06.04.11.07.01.06.04.11.07.15l.08.21s.03.06.03.12c0,.04.02.07.02.09l-.02.2-.09.35s-.03.03-.02.07c0,.04,0,.08-.04.11-.06.03-.16.12-.3.26-.06.12-.12.24-.18.37-.07.1-.12.21-.16.33-.16.27-.3.58-.42.91l-.13.29s-.04.11-.08.25l-.32.66-.07.28-.15.36c-.03.07-.07.17-.13.29-.04.12-.09.25-.14.39-.05.08-.08.17-.1.28,0,0-.04.11-.13.32l-.18.53-.15.49-.14.39-.08.25-.2.44-.04.14c.06.05.03.09-.07.11,0,0,0,.01-.02.04,0,0-.01,0-.04-.02h-.13ZM16.21,57.45l.05-.24v-.06c-.06.08-.1.17-.12.28-.02.03-.02.05-.02.07.02,0,.04,0,.06-.01l.02-.04ZM16.19,56.31l.03-.3c-.03.05-.05.08-.05.08.02-.09,0-.15-.04-.19-.02,0-.03.02-.02.04-.04.03-.06.07-.07.11,0,.04,0,.08-.01.1l.07.02s.04.01.04.06l-.02.07v.03s.07-.01.07-.01ZM35.74,69.18c-.02-.1-.03-.18-.02-.23.01-.05,0-.1-.03-.16-.03-.06-.05-.11-.03-.16.01-.05,0-.1-.03-.16,0-.04,0-.09,0-.13l-.11-.5s-.02-.05-.05-.09c-.03-.02-.04-.03-.04-.06-.03-.02-.04-.06-.06-.12-.02-.08-.04-.14-.07-.18v-.06s-.02-.04-.03-.06c.02-.03.02-.06.01-.1v-.06s.04.12.04.12v.1s0,.03,0,.03h.03c0-.18,0-.32-.03-.43v-.03s-.03-.05-.06-.09c0-.04,0-.06.02-.07.03-.05.03-.11,0-.16-.03-.04-.05-.08-.06-.12.02,0,.02-.02,0-.03,0-.02,0-.03,0-.03.05-.16.03-.26-.06-.28-.08-.05-.11-.1-.1-.14.03-.05.05-.08.05-.08l-.04-.48c0-.2,0-.45-.03-.75l-.03-.42s0-.01,0-.03c0,0-.01,0-.03,0v.03c-.06.1-.09.15-.09.15v-.03s-.02-.06-.02-.06c-.03.05-.05.08-.05.08-.03.18-.02.34,0,.49v.06c-.02.27-.03.47-.02.6l-.04.57s-.03.07-.04.14c0,.07,0,.11,0,.13v.19c0,.15,0,.36.01.62v.23s0,.03,0,.03v-.03s-.03-.09-.03-.09c-.03-.15-.03-.29,0-.43-.02-.1-.03-.18-.02-.23-.03-.15-.03-.25,0-.33.02-.03.01-.09,0-.19v-.56c-.01-.1-.02-.24-.02-.42v-.06s-.01-.05,0-.1c.01-.05,0-.08-.02-.09.02-.03.01-.05-.01-.06-.03-.02-.04-.02-.04-.02l-.06-.12c0-.07.01-.14.01-.23,0-.07,0-.14-.02-.23,0-.09-.02-.23-.06-.41l-.03-.42-.05-.22-.05-.25c-.02-.08-.03-.23-.03-.45v-.03s-.02,0-.04,0c0,0,0,.01,0,.03-.01.05-.02.1-.03.17-.01.05-.02.1-.03.17,0,.39-.02.69-.07.9l.02.23s0,.03-.02.04v-.03s0-.13,0-.13c0,0-.01,0-.03,0,0,0,0-.01,0-.03v.03s-.01.2-.01.2c.01.06,0,.14-.01.23,0,.09,0,.15,0,.19v.03s0-.03,0-.03v-.16s-.03-.06-.05-.06c0,0-.01,0-.03,0,0,0,0,.01,0,.03l.02.23s0,.11,0,.19l-.03.33v.3c.01.26.01.47,0,.62v.03s0-.03,0-.03l-.09-.73v-.23c0-.06-.01-.12-.03-.19,0-.07,0-.14-.05-.22l-.05-.22v-.03s0,.03,0,.03l-.03.33-.03-.29s.02-.01,0-.03v.03c0,.07,0,.14,0,.23,0,.09-.02.18-.04.27,0,.02,0,.03-.02.04-.02,0-.03,0-.03,0v-.03c0-.07,0-.14,0-.23,0-.09,0-.15,0-.19v-.82s-.01-.3-.01-.3c0,0,0-.02-.01-.06.01-.05,0-.06-.04-.06v-.06s0-.26,0-.26c0-.04-.02-.06-.04-.06v.03s0,.1,0,.16l-.04.14s0,.03-.02.04v-.03s-.01-.33-.01-.33v-.06s-.04.04-.04.04c0,.02,0,.03-.02.04l.02.09-.02-.09-.02-1.14v-.23s0-.03,0-.03c0,0-.01,0-.03,0,0,0,0,.01,0,.03v.49s-.02.02-.02.04v-.03s-.01-.03-.01-.03l-.02-.09s-.02.06-.01.1l-.04.27s-.01,0-.03,0c0,0,0,.01,0,.03v-.06s-.02-.16-.02-.16v-.33s-.01-.03-.01-.03l-.02.07v-.06s-.03-.52-.03-.52c-.03-.54-.05-.98-.06-1.33l-.1-1.35-.04-.48c-.01-.06-.04-.09-.08-.08-.18.08-.47.19-.88.32-.13.03-.29.08-.49.17l-1.25.4c-.37.12-.64.23-.82.31-.04,0-.09.05-.14.13-.21.24-.39.55-.55.94l-.1.12c-.11.2-.29.56-.55,1.07-.17.34-.28.58-.33.73-.02.03-.07.15-.15.36l-.02.07c.04.08.02.15-.05.21l-.06.18-.18.4s0,.07-.05.08c-.05.08-.07.11-.07.11-.09.17-.2.49-.32.95-.02.03-.03.11-.05.24l-.02.07v-.06s-.04-.12-.04-.12l.09-.64-.02-.09s-.03-.09,0-.16c.02,0,.03,0,.03,0,0-.02,0-.03,0-.03.02-.09.04-.23.04-.4.02-.03.02-.08,0-.16-.02-.08-.01-.15.02-.2l.34-.86.04-.14-.1.12s-.06.08-.07.15c-.03.07-.05.12-.07.15-.09.19-.17.33-.24.41l-.04.14-.04.11s-.06.02-.06.04l-.04-.02c.03-.05.05-.08.05-.08.02,0,.03,0,.03,0,0-.02,0-.03,0-.03-.01-.06.02-.18.09-.35.06-.14.08-.24.07-.28.01-.13.02-.2.02-.2.02,0,.03,0,.03,0-.03-.02-.04-.02-.04-.02-.02,0-.03.02-.02.04-.04.14-.1.31-.19.5l-.02.07c-.01.13-.04.24-.06.31-.03.07-.09.23-.19.47,0,.02,0,.03,0,.03-.02,0-.03,0-.03,0v-.03s.03-.14.03-.14c-.04-.17,0-.36.1-.58.09-.19.14-.35.16-.46,0-.11.02-.19.08-.25h.03s-.03-.08.01-.11c.02-.03.03-.05.05-.08v-.13c.04-.05.05-.09.05-.11v-.03s-.04,0-.04,0l-.07.11c-.02.11-.07.19-.15.23-.04,0-.07.07-.09.18l-.06.04.02-.07c0-.07.04-.17.1-.32.07-.08.13-.27.17-.56l.02-.07.02-.07-.06.04c-.08.13-.27.5-.58,1.11l-.02.04v-.06s.28-.59.28-.59l.02-.2-.07-.02s-.05.03-.08.08c0,.02,0,.04.01.06-.02,0-.04.02-.06.04l-.03-.13c.03-.05.06-.12.08-.21.05-.08.04-.12-.03-.13h-.03s-.06.05-.06.05l.02-.07c.02-.09.05-.16.08-.21l.1-.32.16-.3.28-.52.18-.37.07-.15v-.06c-.08,0-.11-.02-.09-.05.02-.03.03-.05.05-.08l.02-.04.02-.04v.06s.02.03.02.03h.03s.03-.06.05-.08c.04-.03.07-.06.11-.09l.04-.14v-.03s-.08-.02-.08-.02c0,.02-.01.05-.05.08v.13s-.02,0-.07.01v-.03c.07-.17.11-.27.13-.29.01-.05.03-.09.07-.15.03-.05.05-.1.07-.15.04-.03.07-.09.09-.18.05-.16.08-.27.1-.32l-.04-.02s-.01,0-.03,0c0,0,0-.01,0-.03v-.06s.04-.04.04-.04l.1-.32.15-.2.47-1.02.24-.41.26-.48.02-.04v-.06s-.04.02-.04.04l-.26.48-.13.16s0,.03-.02.04v-.06s.07-.21.07-.21c0-.02,0-.03,0-.03.02-.03.01-.05-.01-.06v-.03c.04-.1.07-.19.1-.28.04-.12.08-.23.13-.32.23-.44.35-.67.35-.67l.19-.47c.09-.28.2-.52.33-.73l.31-.82c.04-.1.1-.21.16-.33.06-.12.12-.28.19-.47l.32-.79c.14-.36.22-.56.23-.61.07-.1.12-.22.15-.36.08-.24.15-.4.22-.51.04-.1.09-.22.15-.36.06-.14.11-.31.15-.49.02-.11.08-.25.18-.4.1-.15.17-.27.22-.34l.1-.12c.03-.05.09-.09.17-.1.08-.02.14-.04.18-.07.16-.08.26-.12.3-.13.08-.02.19-.02.33,0,.05.01.12,0,.23-.02.04,0,.09-.02.16-.03.06-.01.11-.01.13,0,.03.02.06.02.1.01.07,0,.16,0,.26,0,.13,0,.24,0,.33.03.08.05.21.1.39.14l.24.05.12.1c.09,0,.15.02.18.06.05.01.08.02.1.01l.11.04.29.3v.06s-.09.12-.09.12c-.07.1-.1.21-.1.32.04.17.06.31.06.44,0,.13,0,.24,0,.33l.07.64.06.87.04.65c.05.43.08.77.09,1.03,0,.11,0,.23.01.36,0,.11,0,.22,0,.33.01.06.02.13,0,.19-.01.05-.01.1,0,.16l-.02.2c-.04.14-.06.22-.08.25l-.02.07c-.04.14-.02.37.06.71,0,.02.03.03.07.02l.09-.02-.09.05s0,.03-.02.04c-.02,0-.03.02-.02.04,0,.04.02.06.04.06.04-.03.06-.04.06-.04h.03s0,.02,0,.02l-.02.04.07.02s.1-.05.18-.07h.06s-.03,0-.02.02l-.15.07-.02.04h.03s.38-.06.38-.06l.16-.03s.04,0,.06-.01c.04,0,.08,0,.1.01.03.02.08.02.16,0l.4-.12h.06s-.06.03-.06.03c-.12.07-.22.11-.3.13-.02,0-.03.02-.02.04h.03s.16-.04.16-.04l.04.02h-.03s-.09.06-.15.07l-.51.21s0,.01,0,.03c0,0-.01,0-.03,0h.03s.65-.18.65-.18c.12-.03.22-.06.27-.09l.07.02h-.06s-.36.16-.36.16c-.02,0-.09.05-.2.14-.12.07-.23.11-.33.14-.04.03-.1.05-.18.07v.03s.23-.02.23-.02c.02,0,.03-.02.02-.04.03-.05.07-.07.12-.06.04,0,.07-.02.09-.02.02,0,.03,0,.04.02h-.03s0,.04-.02.04h.03s.03,0,.04.02v.03s.04,0,.04,0c0-.02,0-.03,0-.03l.06-.04.49-.17c.12-.03.22-.06.27-.09l.04.02h-.03s0,.04-.02.04h.03s.46-.14.46-.14l.23-.02s-.03.02-.02.04c-.09,0-.16.01-.22.05-.04,0-.07.02-.09.02-.06.03-.16.07-.31.1-.06.01-.11.05-.14.1h-.03s-.06.02-.06.02c-.06.01-.11.04-.15.07-.04.03-.08.05-.12.06l-.06.04s.03,0,.04.02c.02,0,.03,0,.04.02h-.03s-.03.01-.03.01h-.06s.02.11.02.11h.06s.24-.13.24-.13c.05.01.1,0,.16-.03.06-.03.1-.05.12-.06.02,0,.03,0,.03,0h.06s-.01.02-.06.03c-.16.08-.3.13-.42.16l-.08.08s-.03.02-.02.04h.03s.41-.1.41-.1h.1s.03,0,.03,0l.4-.12c.17-.04.28-.07.34-.11l.27-.09.42-.16h.06s.07,0,.07,0h-.06s-.48.22-.48.22l-.3.13-.06.04h.06s.18-.09.18-.09c.19-.04.42-.11.71-.22.1-.02.24-.07.39-.15l.49-.17c.13-.03.22-.06.27-.09.04,0,.04,0,0,.03,0,0,0,.01,0,.03,0,0,.01,0,.03,0,.02,0,.03-.02.02-.04l.68-.18.95-.3.25-.05h.03s-.03.01-.02.03l-.24.09-.6.26-.39.15c-.08.02-.15.04-.21.08-.26.1-.45.2-.56.29l-.6.26-.76.26-.63.27-.6.23-.51.21-1.14.48s-.08.06-.14.1c-.06.01-.11.04-.15.07-.04,0-.06.03-.05.08l.02.39v.46c.02.06,0,.12-.03.17,0,0-.01,0-.03,0,0,0,0,.01,0,.03v-.03s-.02-.23-.02-.23l-.02-.23v-.1s-.02-.13-.02-.13l-.07.11v-.03s-.05-.06-.07-.12v-.03s-.03.04-.03.04v.19c.01.11.03.26.07.44-.02.03-.02.05-.02.07.02,0,.04-.02.06-.04.02,0,.02,0,0,.03l-.05.08c-.03.07-.04.16-.04.27.02.08.03.15.04.19.08.35.11.62.11.8l.03,1.04c0,.11,0,.35,0,.72.02.17.02.33,0,.49-.01.13-.02.26-.02.36.01.37,0,.69-.02.95-.03.27-.04.48-.03.63,0,.18,0,.31.02.39,0,.04.01.06.01.06.03.06.04.13.02.23l-.03.33-.07.44c.01.06.01.12,0,.16-.03.38-.04.58-.03.6-.02.03-.02.07,0,.13v.13c0,.24,0,.4-.03.5,0,.22.02.38.04.48l.04.65c.02.08.03.17.02.26,0,.09,0,.16.02.23,0,.04,0,.12-.01.23,0,.13.03.24.07.34v.03s-.05.02-.05.04c0,.04.02.07.02.09-.02.09-.03.17-.01.23h-.03s0-.02,0-.02ZM26.48,61.37l.04-.14v-.03s-.04.02-.03.04c-.03.05-.05.09-.04.11v.03s.04,0,.04,0ZM35.15,66.46s-.04-.02-.05-.09v-.13s.04,0,.04,0c.01.06.01.11,0,.13l.02.09ZM33.72,64.11s0-.03,0-.03c.02,0,.03,0,.03,0-.02-.08-.02-.17,0-.26v-.06s-.02-.03-.02-.03l-.02.04v.33s.01.03.01.03ZM34.01,64.22s.05-.03.08-.08c-.02,0-.03,0-.04-.02,0-.02,0-.03,0-.03-.04,0-.06.04-.04.11v.03ZM34.59,64.78c.03-.05.05-.08.05-.08l-.02-.09-.04.11v.06ZM34.05,63.95l.02-.07c-.01-.06-.01-.12,0-.16h.03s0,.02,0,.02c0-.02,0-.03,0-.03.02,0,.03,0,.03,0l-.08-.21v-.03s-.04.02-.03.04c-.01.13-.01.24,0,.33-.02.03-.02.07,0,.13,0,0,0,.02.01.06l.02-.07ZM33.76,63.22s-.02-.03-.04-.02v.03s0,.08,0,.16c-.01.05-.01.1,0,.16l.03-.33ZM34.62,63.89s.02-.07,0-.13h.03c-.02-.09-.04-.15-.07-.19v-.03s0,.03,0,.03v.33s.04,0,.04,0ZM34.07,63.32c.02-.09.03-.17.01-.23,0-.07,0-.12,0-.16l-.02-.09v-.03s-.04.02-.03.04v.03c-.04.08-.05.14-.01.2v.1c-.04.05-.05.11-.04.17l.04.06.05-.08ZM33.52,62.29s.02-.05.02-.07c0-.04,0-.08.01-.1v-.06s-.03.07-.03.07l-.02.07.02.09v.03s0-.03,0-.03ZM34.09,62.66v-.03c-.02-.06-.02-.12,0-.16l-.04-.02v.03s-.03.14-.03.14c-.04.03-.04.05-.02.07.03.02.04.03.04.06h.03s.02-.08.02-.08ZM34.07,62.27l.02-.07c-.02-.08-.02-.19,0-.33v-.03s-.01-.03-.01-.03h-.03s0,.46,0,.46l.04.02v-.03ZM33.51,61.64s.03-.02.02-.04v-.1s-.02-.13-.02-.13v-.06s-.03.07-.03.07c.02.1.03.18.02.23v.03ZM28.22,57.06s.06-.02.06-.04c.02-.03.02-.05.02-.07.04,0,.07-.03.09-.05.02-.03.02-.05.02-.07.01-.05.04-.1.1-.15.05-.06.09-.11.1-.15.03-.05.04-.11.03-.17.02-.03.02-.06.01-.1h.03s0,.03.01.06c.02,0,.03-.02.02-.04.04-.03.05-.08.04-.14,0-.07.02-.11.04-.14,0,0,0-.01,0-.03,0-.02-.02-.03-.04-.02-.02,0-.04.02-.06.04,0,.02,0,.01-.04-.02v.06s0,.08-.01.17c-.04.03-.06.07-.07.11-.01.05-.03.08-.04.11-.02,0-.03.03-.02.07.02,0,.03-.02.02-.04l.04.02s0,.07-.05.08c-.05-.01-.09,0-.12.06-.05.08-.07.11-.07.11.03.04.04.08.03.12-.01.05-.03.08-.04.11,0-.04-.03-.07-.05-.09l-.05.21h.03ZM33.76,61.29s0-.03,0-.03c.02,0,.03,0,.03,0-.02-.08-.02-.19,0-.33v-.06s-.07-.09-.07-.09v.1s0,.05-.02.1c0,.02.02.05.05.09v.19s.02.03.02.03ZM34.09,61.58v-.46s0-.03,0-.03v-.06s-.03.07-.03.07v.16s0,.33,0,.33v.03s.03-.04.03-.04ZM28.88,55.87s0-.08.01-.1v-.06s-.04.04-.04.04c-.03.05-.04.1-.04.14l.02.09.04-.11ZM34.05,60.8s0-.03,0-.03c.02-.03.02-.05.02-.07.01-.13.01-.23,0-.29.01-.13.01-.23,0-.3v-.03s0,.01,0,.03c0,0-.01,0-.03,0v.06s-.01.33-.01.33v.03s0-.03,0-.03v-.1s-.03-.06-.03-.06v.03s0,.1,0,.16c0,.04,0,.09-.04.14l.02.09s.03.03.07.02ZM29.01,55.54c.08-.04.11-.08.1-.12v-.03s-.02-.03-.04-.02c-.07.1-.1.15-.1.15v.03s.04,0,.04,0ZM33.57,60.09v-.13s-.03-.29-.03-.29v-.03s-.03.04-.03.04l.03.42v.03s.03-.04.03-.04ZM33.47,59.81c0-.18,0-.31-.02-.39v-.03s0,.03,0,.03l-.02.2v.16s0,.03,0,.03h.03ZM28.93,54.91v-.03c-.08.08-.12.14-.13.19v.03s.13-.19.13-.19ZM29.23,55.37v-.06s.02-.14.02-.14c0,0,0-.02-.01-.06l-.06.18v.06s0,.07,0,.07l.06-.04ZM33.54,59.5l.02-.04v-.06s-.03-.06-.03-.06c0,.02,0,.03-.02.04v.13s.04.06.04.06v-.06ZM33.39,59.27v-.06s-.03-.06-.03-.06c0-.02,0-.03,0-.03.02,0,.03,0,.03,0l-.04-.02s0,.01,0,.03c0,0-.01,0-.03,0l.02.09v.06s.04,0,.04,0ZM33.7,59.63c-.01-.06-.01-.12,0-.16l.02-.04h.03s0-.04,0-.04l-.04-.02-.04-.02v.03s0,.23,0,.23v.03s.01.03.01.03l.02-.04ZM28.98,54.83l.07-.15v-.03s-.04,0-.04,0l-.07.15v.03s.04,0,.04,0ZM29.35,55.14s0-.06.04-.11l-.02-.09c-.05.08-.07.11-.07.11,0,.04.03.07.05.09ZM29.27,54.96s0,.03,0,.03c.02,0,.03-.02.02-.04l.1-.12-.04-.02s-.01-.02-.03,0l-.07.11v.03ZM31.24,56.76s.05-.04.09-.05h.06s.06-.06.06-.06h-.06s-.06.03-.06.03c-.06.01-.09.04-.08.08-.05-.01-.11,0-.19,0h-.06s.07.03.07.03l.19-.04ZM33.74,59.23s.03-.02.02-.04v-.03s-.01-.03-.01-.03l-.04-.06s0,.01-.02.04c0,0,0,.01-.02.04v.03s.04,0,.04,0l.02-.04v.03s.01.03.01.03v.03ZM34.03,59.5s.03,0,.03,0c0-.02,0-.03,0-.03.01-.05.01-.1,0-.16v-.03s-.03.04-.03.04v.13s0,.06,0,.06ZM29.44,54.83c.03-.05.05-.09.04-.11l-.03-.13c-.03.05-.05.09-.04.11l.03.12ZM29.61,54.56s.02-.04.07-.11c-.07-.03-.11-.05-.11-.07-.03.05-.05.08-.05.08-.02.03-.02.05-.02.07,0,.02.02.04.04.06l.04.06.02-.07ZM34.02,59.17s0-.03.02-.04c.02,0,.03-.02.02-.04v-.26s-.03-.19-.03-.19l-.04-.02v.03c.03.1.03.18.02.23v.03c.02.06.01.13-.01.2v.06ZM33.72,58.52s-.02-.03-.04-.02l-.06.04.04.06.05-.08ZM29.71,54.41c.03-.05.05-.08.05-.08l-.04-.02s-.06.02-.06.04l.04.06ZM29.43,54.47l.08-.21.2-.3v-.03s-.04,0-.04,0l-.16.33-.12.22v.03s.03-.04.03-.04ZM29.78,54.26c.03-.05.05-.08.05-.08.04-.03.07-.1.08-.21l.06-.18.06-.18s.03-.02.02-.04h-.03s-.04.06-.08.09c-.04.03-.04.07,0,.13-.03.05-.06.08-.08.08-.02,0-.04.02-.06.04-.02.03-.02.05-.02.07.02.08,0,.13-.04.14-.02.03-.02.06-.01.1l.04.02ZM29.72,53.39l.05-.08s-.03,0-.04-.02l-.07.15v.03s.06-.08.06-.08ZM29.93,53.48l.09-.18v-.03s-.04,0-.04,0l-.05.21s-.08.04-.11.09c-.03.05-.04.1-.04.14h.03s.12-.23.12-.23ZM30.16,53.46l.05-.21v-.03s-.04,0-.04,0l-.09.18.03.13.05-.08ZM31.14,55.87s.03,0,.04.02c.02,0,.04-.02.06-.04l.7-.25.69-.15c.05-.06.08-.09.07-.11l-.02-.09-.1-.76-.06-.44c0-.07,0-.14-.02-.23l-.03-.12c-.03.05-.05.08-.05.08v.03s-.5.96-.5.96c-.07.1-.12.17-.15.2-.06.03-.12.1-.18.2l-.1.28c-.02.09-.05.16-.08.21-.07,0-.12.01-.15.07-.02.03-.04.05-.08.08,0,.04,0,.06-.02.07ZM30.41,52.98s.03,0,.03,0c0-.02,0-.03,0-.03.03-.05.05-.09.04-.11.03-.05.06-.12.08-.21v-.06s-.03-.06-.03-.06l-.02.07-.02.07s-.03.06-.04.11c0,.02-.01.04-.06.04v.03s.01.08,0,.1v.03s.01.03.01.03ZM33.15,55.17s.05-.06.05-.08l-.03-.16.02-.07s-.05.04-.09.05v.13s0,.06,0,.06l.04.06ZM33.01,55.1l.02-.5s-.02-.03-.04-.02v.03s0,.26,0,.26c.02.08.02.16.02.23v.03s0-.03,0-.03ZM30.63,52.47l.07-.15-.04-.06h-.03s0,.08-.03.18v.06s.04-.04.04-.04ZM33.27,55.11s.03-.03.02-.07c0-.09,0-.19-.04-.32v-.06s-.04.04-.04.04l.06.41.02.09-.02-.09ZM33.15,54.84l.04-.14-.04-.06-.02.07s-.05.07-.04.11v.03s.07-.01.07-.01ZM33.54,55.15s.06-.02.06-.04c.02,0,.02-.01,0-.03,0-.02,0-.03,0-.03-.05-.01-.06-.06-.03-.16,0-.02,0-.02.03,0h.03s-.02-.04-.04-.03c-.06-.05-.07-.11-.03-.16v-.06s-.05-.02-.05-.02v.03s-.01.06,0,.1c0,.02,0,.04-.02.07l.06.28v.06ZM33.53,54.07s-.01-.06-.01-.06c0-.02-.03-.03-.07-.02,0-.02-.01-.02-.03,0l.07.02.04.06v.06s0-.06,0-.06ZM34.27,54.73v-.13s0-.06,0-.06c-.03.05-.05.08-.05.08,0,.02,0,.04-.02.07,0,.02.02.04.04.06,0,.04.02.06.04.06v-.06ZM33.06,53.55s.01-.04,0-.03v-.33s-.02,0-.04,0c0,0,0-.01,0-.03v.03c0,.07,0,.16.04.29v.06ZM33.94,54.14l.02-.07s-.02-.03-.04-.02c0-.02,0-.04-.01-.06v.06s0,.06,0,.1l.04.06v-.06ZM35.48,53.81s0-.03,0-.03c.02,0,.03,0,.03,0,.04-.14.05-.23.04-.27l-.13-.59v-.03s0,.03,0,.03l.06.74v.13s0,.03,0,.03ZM38.31,54.93c.07-.06.13-.09.17-.1.02-.03.03-.03.03,0,.02,0,.04,0,.06-.01l.07.02h-.06c-.08.03-.14.06-.18.09l-.09.02ZM44.8,62.85s-.06,0-.11-.04v.06s-.1-.07-.1-.07l-.04-.02c-.07,0-.16,0-.29.03-.05-.01-.11,0-.19,0-.02,0-.05.01-.09.02-.02.03-.06.03-.12.03h-.19s-.1,0-.16.01c-.06.03-.11.06-.15.07l-.09.02h-.43s-.09.02-.09.02c-.02,0-.06,0-.11-.04l.02-.04c0-.09.04-.14.1-.15.06-.01.1-.02.12-.03.03.02.04.01.03,0,.02,0,.04,0,.06-.01-.04,0-.08,0-.1-.01-.1.02-.18.03-.23.02,0,0-.01,0-.03,0,0,0,0-.01,0-.03v-.03c.07-.06.12-.12.15-.17-.07.06-.14.1-.21.11-.1.06-.17.08-.22.05-.13-.01-.24,0-.32.04-.04.03-.1.05-.18.07-.17.04-.36,0-.58-.1-.29-.13-.62-.4-.99-.8-.27-.25-.47-.43-.58-.56-.24-.3-.4-.52-.48-.68-.15-.29-.27-.63-.35-1l-.04-.19c-.02-.1,0-.17.05-.21.02,0,.02-.04.01-.1v-.33s-.02-.06-.02-.06l.04-.11.02.09.07.31v.06s.12.04.12.04v-.06s-.15-.63-.15-.63v-.03s.05-.21.05-.21c.03-.05.05-.08.05-.08l.04.06v.06s.06-.08.06-.08v-.16c.02-.09.03-.16.02-.2-.04-.17-.05-.29-.05-.38,0-.04-.02-.13-.02-.26-.01-.15,0-.29.04-.43.04-.1.07-.18.08-.25.02-.09.05-.17.08-.25,0-.02,0-.04-.01-.06.02-.03.01-.05-.01-.06v-.03c.03-.05.05-.12.08-.21.04-.12.07-.21.1-.28.02-.03.02-.05.02-.07,0-.04,0-.08.01-.1,0-.02,0-.06.04-.11.03-.05.03-.11,0-.16h.03c.06-.04.06-.06.02-.08-.03-.04-.03-.06-.01-.06v-.03c-.07,0-.1-.03-.09-.08.06-.14.09-.25.1-.32l.02-.07-.06.04c-.02.09-.05.18-.07.28-.03.07-.05.13-.06.18-.04.1-.09.24-.14.42-.02.11-.05.28-.09.51-.04.21-.06.39-.04.57,0,.02,0,.07-.04.14-.01.05,0,.08.05.09-.04,0-.07.04-.08.08,0,.04.02.07.02.09-.03.05-.06.14-.07.28l.03.42c.02.08.01.15-.02.2-.03.05-.04.12-.02.2l-.02.07-.05-.22c-.02-.1,0-.18.05-.24,0-.04-.01-.06-.01-.06-.05-.23-.05-.44,0-.62l.07-.28.04-.14-.03-.12.07-.6c0-.26.08-.55.2-.86.22-.7.46-1.3.72-1.79.2-.48.36-.83.49-1.06,0,0,.07-.1.2-.3.09-.19.17-.33.24-.41l.38-.67c.09-.19.24-.49.46-.89l.33-.6.33-.43c.03-.05.08-.1.13-.16.05-.08.07-.16.08-.25,0-.07.08-.2.21-.41.04-.1.11-.21.19-.34.08-.13.15-.24.22-.34l.05-.24c-.02-.17.06-.33.22-.47l.54-.51.07-.15.04-.11c.06-.03.2-.2.42-.48l.28-.22c.14-.16.24-.29.31-.39.12-.14.32-.28.6-.42.12-.05.31-.1.56-.15l.12-.06.27-.09c.08-.04.15-.05.22-.05.06-.01.11-.03.16-.03.13-.03.23-.02.3.03.09.02.21.04.34.06.15-.01.26-.01.33,0l.72.14s.11.07.34.22c.03.02.04.05.05.09.2.31.29.56.26.76,0,.11-.02.26-.07.44l.02.55s-.02.09-.04.14c-.02.03-.03.06-.04.11l-.08.21c0,.22,0,.37-.03.46,0,.04-.02.19-.1.45l-.07.15s0,.05-.01.1c-.02.03-.04.03-.06.01-.02,0-.03.02-.02.04-.03.16-.09.36-.17.59-.06.21-.13.46-.19.76l-.11.25c-.03.05-.04.12-.02.2,0,.13-.05.22-.17.27l-.09.18c-.04.21-.12.42-.22.64-.16.38-.24.61-.25.68-.12.35-.3.73-.54,1.13l-.35.34-.07.11-.1.15c-.06.01-.11.01-.13,0-.08-.05-.17-.05-.3,0-.13.09-.26.18-.37.24l-.18.07c-.29.06-.55-.08-.78-.42-.03-.06-.11-.14-.22-.25-.22-.21-.34-.43-.37-.64-.03-.13-.03-.32,0-.59.05-.25.1-.47.15-.66.05-.18.09-.36.12-.52l.13-.45v-.06s-.06,0-.08.01c-.03-.02-.04-.01-.03,0-.06.03-.12.1-.18.2l-.52.77-.51.8s-.09.18-.32.63l-.52.9c-.12.24-.24.51-.35.8-.04.1-.07.18-.08.25,0,.07-.02.12-.03.17l-.2.6-.15.66v-.03s-.06.03-.06.08c0,.07-.02.15-.05.24-.03.07-.04.15-.05.24l-.04.73.05.38.02.09.07.02.02-.07s0-.04.02-.07c.02-.03.04-.02.07.02.03.02.05.03.08.05.02,0,.03,0,.04.02.02.08.01.15-.02.2,0,0-.03.05-.1.15v.03c-.06-.03-.13,0-.17.07-.07.17-.09.33-.06.47-.02.03-.04.03-.06.01h-.03s-.04.06-.02.08c.02,0,.03,0,.04.02,0,0,.03.02.08.05v-.1s0-.06,0-.06l.09-.05.09-.02s-.03.02-.02.04l-.05.21v.1s0,.06,0,.06l.08.05v-.1s.04-.33.04-.33l.16.29.26.44.08.05v-.1s.03-.07.03-.07v.03c.06.03.09.06.09.08-.02.03-.03.06-.04.11-.02.03-.05.04-.09.05,0,0,0,.01-.02.04,0,0,.01,0,.04.02.05.03.05.07-.01.1-.02.03-.02.06-.01.1.12.17.26.29.41.37.07.03.14.07.19.12l-.04.11h-.03s-.04,0-.07-.01c-.03-.02-.03-.04-.01-.06l-.04-.02s-.01,0-.03,0c0,0,0,.01,0,.03l.02.09c.02.08.09.15.2.18.02,0,.04,0,.07.02.05.01.06.04.05.09,0,0,.04.03.12.1l.04.06c0,.07.01.11.06.12.04,0,.08-.03.12-.06.22-.07.51-.19.84-.35.32-.16.55-.28.7-.38h.03s-.17.13-.17.13l-.02.04h.06s.21-.09.21-.09c0,0,0,.01,0,.03,0,0,.01,0,.03,0-.02,0-.03.02-.02.04-.11.09-.18.15-.19.17-.06.03-.11.07-.14.1-.02.03-.03.05-.05.08-.02,0-.03.02-.02.04,0,0,0,.01,0,.03,0,0,.01,0,.03,0,.06-.01.14,0,.23.01l.25-.05v.03s.07-.01.07-.01l.23-.15h.03s0,.03-.02.03l-.43.26-.37.28-.21.11-.32.2h-.06s-.07-.02-.13,0c-.04.03-.08.05-.12.06-.03-.02-.05-.02-.07-.02h-.1c-.05-.04-.12-.03-.22.04l-.13.03s-.03,0-.04-.02h.03s.02-.04.02-.04l-.07-.02c-.13-.01-.22-.02-.26,0l-.37.11-.26.16s-.02-.06-.04-.06l-.12.06v.03s0,.01.01.03c0,0,.01,0,.03,0h-.06s-.04-.04-.04-.04v.06s.03.06.03.06c-.04,0-.06.01-.06.01-.03-.02-.05-.01-.06.01,0,.02-.02.04-.09.05v-.03s.02-.02.02-.04l.1-.12-.04-.06s-.09.02-.16.03c-.07,0-.1.02-.11.09,0,.02,0,.03-.02.04l-.07.11c.05.03.09.05.11.04.05.01.11,0,.19,0,0-.02,0-.03.02-.04,0,0,0,.01,0,.03,0,0,.01,0,.03,0,0,.04.03.06.08.05l.12-.06c.05.03.09.05.11.04.02,0,.05-.03.08-.08-.02,0-.04-.01-.04-.06l-.16.03s-.02-.03-.04-.02h.03s.14-.1.14-.1c-.03-.02-.03-.03,0-.03.02,0,.03-.02.02-.04v.06s.07-.04.07-.04h.03s.09,0,.13-.03c.04-.03.07-.05.09-.05l.21-.08.25-.05s.08,0,.1.01l-.06.04-.27.12s-.03.02-.02.04c0,.02.03.03.07.02l.12-.03c.06-.01.11-.05.14-.1.02,0,.03,0,.04.02l-.06.04.07.02.16-.03c.13-.03.27-.08.42-.16.02,0,.03,0,.04.02l-.08.08s-.03.02-.02.04h.03c.08-.02.14-.05.18-.08l.04.02h-.03s-.05.08-.05.08l.09-.02.22-.05.06-.04.17-.13s0-.02,0,0c.02,0,.03,0,.03,0l.09-.02c0-.07.04-.1.11-.09.02,0,.06-.04.1-.12.02,0,.03-.03.02-.07l-.06.04c-.12.07-.21.11-.27.12l-.06.04v.03s-.06,0-.06-.02c0-.02,0-.03.02-.04.03-.05.08-.08.14-.1l.25-.19h.03s0,.02,0,.02c-.02.03-.02.05-.02.07.02,0,.03,0,.03,0,.03.02.06.02.1.01.07-.06.13-.09.17-.1v-.03s-.04,0-.04,0c0-.02-.02-.03-.04-.02,0-.02,0-.03.02-.04l.06-.04c.29-.19.55-.33.8-.4l-.09.05-.02.04h.06s.02-.05.02-.05v.06s.05.02.05.02l.33-.14.41-.22.07.02s-.03.02-.02.04c-.04.03-.1.09-.19.17l-.41.38.32-.17c.1-.06.17-.12.22-.18.07-.06.14-.11.2-.14h.19s.09-.06.09-.06l.09-.05h.06c.12-.08.2-.14.25-.2.09-.09.2-.17.33-.27.13-.12.26-.23.38-.35l.16-.17h.03s0,.02,0,.02l-.6.56c-.11.11-.27.26-.49.44l-.05.08h.06c.1-.06.29-.19.57-.4.09-.09.19-.16.31-.23,0-.02,0-.03,0-.03.02,0,.03,0,.03,0l1-.81h.06s-.02.02-.02.02l-.79.73s-.02.03-.05.08c0,0-.02.03-.05.08.06-.01.09-.03.09-.05l.4-.28c.27-.26.41-.38.41-.38l.39-.31c.06-.03.11-.07.14-.1.06-.03.11-.07.14-.1l.33-.27.17-.13s0-.02,0,0c.02,0,.03,0,.03,0v.03s-.04.03-.07.08c.06-.01.1-.03.12-.06l.33-.3.08-.08v.03s.01.03.01.03h.03s.14-.13.14-.13h.06s-.03,0-.02.02l-.36.47-.6.72c-.11.11-.22.22-.35.34-.13.12-.25.24-.38.38-.24.18-.45.36-.61.52h-.1s-.03,0-.03,0c0,0,0,.01-.02.04,0,0,.01,0,.03,0,.03.04.03.07-.01.1-.02.03-.03.04-.06.04-.29.28-.49.47-.6.56-.26.23-.4.36-.44.39-.03.05-.07.08-.11.09-.02.03-.03.04-.06.04h-.03s0-.02,0-.02l.18-.24.39-.31.17-.13s.02-.03.05-.08l-.09.02-.28.22c-.09.09-.2.16-.34.24-.13.12-.32.27-.59.46-.04.03-.05.06-.05.08,0,.02,0,.04-.02.07l.04.06s0-.06.02-.07c.04,0,.07-.02.09-.02l.14-.13.11-.09.09-.02-.02.07-.3.26c-.05.06-.1.08-.15.07l-.05.08-.09.05c-.06.01-.1.03-.12.06,0,.07-.05.12-.13.16-.06.03-.11.07-.14.1l-.17.13s.05-.12.12-.22l.08-.08s-.02-.03-.04-.02l-.13.03c-.09,0-.16.01-.22.05-.05.06-.13.1-.23.15-.1.06-.17.11-.23.15h-.03s-.01-.06-.01-.06c-.05-.01-.1.01-.15.07l.02.09v.03s-.05.02-.05.04l-.1.12c.06-.01.1-.03.12-.06.06-.01.11-.05.14-.1h.03s0,.03-.02.03c-.03.07-.05.12-.07.15-.17.23-.4.36-.7.38ZM41.37,62.42l-.18-.09-.11-.04-.02.04s.02.06.04.06c.14.04.22.06.25.08h.03s0-.04,0-.04ZM41.56,62.24s.03-.02.02-.04h-.03c-.07,0-.17.01-.32.04v.03s.33-.04.33-.04ZM40.3,60.98s-.01,0-.03,0c0,0,0-.01,0-.03v-.06s-.09-.05-.09-.05l-.06.04s.03.02.08.05l.04.06h.06ZM40.06,60.77l-.08-.08-.06.04.11.07.02-.04ZM42.56,62.32v.03s.07-.01.07-.01l.41-.22c.08-.02.09-.05.01-.1-.05-.03-.07-.03-.06.01l-.06.04s-.05.02-.09.05c-.02.03-.04.03-.06.01-.03-.02-.12.01-.27.09l-.12.06-.09.05h-.03s-.03-.05-.08-.04c-.02.03-.03.03-.03,0-.02,0-.03.02-.02.04-.02.03-.05.04-.09.05-.04.03-.07.04-.09.02-.05-.03-.12-.04-.2-.02l-.14-.04h-.06c.05.05.08.06.08.06l.5.05.16-.03.27-.12ZM41.7,61.69l-.14-.04-.02.04s.06,0,.11.04l.06-.04ZM41.94,61.74s.03-.02.02-.04c-.09-.02-.17-.03-.23-.01h-.03s0,.04,0,.04c.02,0,.03,0,.03,0,.09.02.16.03.2.02ZM39.91,60.67s.03-.03.02-.07l-.04-.06-.13-.14s-.02-.06-.06-.12c-.04-.08-.09-.13-.17-.16h.03s0-.04,0-.04c-.03-.06-.05-.11-.03-.16l-.07-.02h-.03s-.07-.01-.07-.01v.03s.1.11.1.11c.07.12.13.21.19.29,0,.02.04.07.1.14l.13.17.04.02ZM42.41,62.09s.06-.02.06-.04c-.01-.06.03-.11.14-.13v-.03s-.04,0-.04,0l-.13.03c-.13.03-.21.03-.26.02l-.06.04s.03,0,.04.02c.03.02.05.02.07.02.04,0,.08,0,.1.01,0,.02.02.03.04.02.02,0,.03,0,.04.02ZM41.1,60.9s-.06-.04-.19-.12l-.02.07c.09.02.16.05.21.08v-.03ZM42.75,61.85l-.04-.02s-.05.03-.08.08h.03s.09-.06.09-.06ZM39.33,59.85s.06-.02.06-.04l-.02-.09-.07-.02-.04-.19-.11-.34-.07-.02-.02.07.05.22.18.35.04.06ZM40.04,59.95l-.08-.05v.03s.09.08.09.08v-.06ZM39.96,59.84l-.06-.12-.02.07.08.08v-.03ZM42.74,61.5s.03-.02.02-.04h-.03s-.23.02-.23.02h-.03s-.06.05-.06.05l.04.02.28-.06ZM41.18,60.52l-.11-.07h-.03c.05.04.08.07.08.09.02,0,.03,0,.04.02h.03s0-.04,0-.04ZM39.86,59.7l-.06-.12s-.03.03-.02.07l.05.09.02-.04ZM40.54,60.14s-.03-.07-.05-.09v-.06c-.08.01-.11.01-.11-.01,0-.04-.02-.07-.02-.09h-.03s0,.02-.02.04c0,0,.01,0,.03,0,.02.08.07.15.14.2,0,.02,0,.03,0,.03.02,0,.03,0,.03,0h.03ZM40.98,60.21s-.04-.07-.1-.14l.07.15s0,.03,0,.03c.02,0,.03,0,.03,0v-.03ZM40.04,59.76c-.04-.08-.08-.16-.12-.24-.04-.1-.1-.19-.16-.26,0-.02,0-.03,0-.03.02,0,.03,0,.03,0l.28.53h-.03ZM39.66,59.38s.03,0,.03,0c0-.02,0-.03,0-.03l-.12-.27s-.02-.03-.04-.02v.03s.06.14.14.3ZM42.85,61.57c.08-.02.15-.04.21-.08.09,0,.2-.01.35-.04l.11-.09h-.1s-.34.06-.34.06c-.07,0-.11,0-.13.03,0,.02,0,.03-.02.04v-.03s-.02-.03-.04-.02h-.03s.04.08.02.1c-.02,0-.04,0-.06.01l-.02.04s.06-.01.06-.01ZM43.51,61.59l-.07-.02-.06.04h.1s.02-.03.02-.03ZM44.39,61.99l-.04-.02-.1.12.04.02.1-.12ZM44.76,62.66l.29-.16s.02-.03.05-.08l.02-.04v.03s.08.02.08.02l.02-.04s.02-.01,0-.03c0,0-.03-.02-.08-.05l.02-.07.09-.02-.07-.02h-.03s0-.02,0-.02c.02,0,.03,0,.03,0,.07-.06.13-.12.16-.17l.05-.08-.09.02-.09.02-.09.02-.29.19s.02-.06.01-.1l-.09.02s0,.03-.02.04h-.06s.05-.06.05-.06l.02-.04.09-.02c.13-.03.24-.09.35-.18l.02-.07h-.06s-.17.12-.17.12l-.04-.02c.03-.05.03-.08-.02-.09-.04,0-.06,0-.07-.02,0,.02-.01.04-.06.04l-.05.08-.2.14c-.05.06-.05.1,0,.13,0,.02-.01.05-.05.08-.01.05.02.05.1.01l.04.06s-.05.03-.08.08l-.32.2s0,.06-.04.11c.02,0,.03,0,.03,0,.03.02.05.01.06-.01.06-.01.19-.06.39-.15l.07.02-.06.04-.06.04.11.04h.03ZM43.87,61.45c.05-.08.07-.11.07-.11l-.07-.02c-.03.05-.06.08-.08.08,0,.04.03.06.08.05ZM45.37,62.17l-.04-.02s-.02.03-.05.08l.07.02.02-.07ZM40.74,60.75c.03-.05.05-.09.04-.11-.01-.06-.06-.12-.13-.17l-.22-.28c-.07-.12-.15-.24-.24-.37-.07-.14-.15-.28-.23-.44l-.04-.02h-.03s-.03-.12-.03-.12c-.09-.2-.16-.35-.23-.44l-.07-.15v-.13s-.09-.27-.09-.27c0-.11-.01-.25-.03-.42-.02-.17-.03-.3-.05-.38l.02-.2c.02-.09.03-.25.03-.47l-.04-.02s-.01.04-.06.04l.02-.07v-.06s-.03-.03-.05-.02l-.02.04-.04.27c-.02.11-.02.32,0,.62,0,.11.02.26.06.44l.16.75.09.27.21.35c.07.2.16.4.29.59.12.17.2.28.24.34l.13.14v.06s-.02.03.03.06c.03.04.1.09.2.15,0,.02.02.03.04.02.02,0,.03,0,.03,0ZM42.25,60.16s0-.03,0-.03c.02,0,.03,0,.03,0,0-.02-.02-.03-.04-.02,0-.02,0-.04-.01-.06v.1s0,.01,0,.03c0,0,.01,0,.03,0ZM43.84,60.99v-.03s-.08-.02-.08-.02h-.06s-.06.04-.06.06c.02,0,.03,0,.04.02h.03s.12-.03.12-.03ZM40.13,58.82l-.26-.76s-.01,0-.03,0c0,0,0-.01,0-.03v.06s.04.13.04.13c.04.17.1.37.2.61l.04.02.02-.04ZM42.48,60.77s0,.03,0,.03c.02-.03.02-.05.02-.07.04,0,.06-.03.05-.08l-.16-.13c-.12-.15-.22-.26-.3-.33v-.06c.05,0,.07,0,.04-.04,0-.04-.01-.06-.01-.06l.04-.11.08.05s.03.02.08.05l.02-.04-.08-.08s-.02-.03-.04-.02v.03s-.06-.02-.06-.02l.06-.04s-.01-.06-.01-.06l-.13-.17c-.14-.14-.23-.28-.28-.4-.01-.06-.05-.15-.12-.27l-.17-.49s-.03-.05-.08-.08l.02.09s.03.13,0,.26c0,0,0,.01-.02.04,0,0,0-.01,0-.03l-.04-.06-.08-.21-.04-.02v.03s.02.06.02.06c.01.06.04.14.09.24.04.08.05.15.05.22.03.04.04.08.03.13,0,.04.02.08.03.13.02.1.09.32.21.64,0,.02,0,.04.01.06.02,0,.02,0,0,.03-.01.05-.01.1,0,.16.01.06.04.11.07.15l.32.26s.03,0,.04.02l-.09.02-.02.04s.04.03.04.06c0,.02.02.03.04.02.07,0,.21.02.43.04ZM40.21,58.48s.06-.02.06-.04c.01-.05.02-.08.01-.1l-.04-.02-.07.11.04.06ZM41.06,58.91l-.03-.16-.02-.09-.04-.06-.02.07s.06.12.09.24c0,0,0,.01,0,.03,0,0,.01,0,.03,0v-.03ZM40.2,58.25c-.02-.1-.05-.17-.08-.21l-.02-.09h-.03s-.02.08-.02.08l.09.24v.06s.06-.08.06-.08ZM43.95,60.58c.08-.02.16-.07.23-.15h.03s-.03,0-.03,0c0-.02,0-.03,0-.03l-.26.15s0,.01,0,.03c0,0-.01,0-.03,0h.06ZM40.84,58.21l-.09-.41-.02-.09-.04-.02-.02.04-.04.14s0,.03-.02.04h.06s0,.02,0,.02c.02,0,.03,0,.03,0l.07.18.03.12.04.06v-.06ZM46.53,61.75s.05-.03.08-.08l-.04-.02-.08.08s.04.02.04.02ZM40.42,57.91s-.03-.04-.01-.06c.01-.05.02-.08.01-.1.03-.07.03-.12,0-.13-.02-.08,0-.14.03-.17v-.06s-.02-.09-.07-.12c-.03-.04-.06-.06-.08-.08,0-.02-.02-.03-.04-.02,0-.02,0-.03,0-.03.02,0,.03,0,.03,0h-.03s.01.07.01.07l-.02.07h-.03s0-.02,0-.02l-.02.04.07.31h-.03s.1.15.1.15l-.02.04s-.03.02-.02.04c.03.02.04.02.04.02,0,.02.03.05.08.08v.03s.03-.04.03-.04ZM39.72,57.27s0-.03.02-.04l-.04-.32v-.03s-.04.02-.03.04v.29s.04.06.04.06ZM45.2,60.76v-.06s.04-.04.04-.04v.03s.01.03.01.03c0,0,0,.01,0,.03.02,0,.03-.02.02-.04l.23-.15v-.03s.01-.07.01-.07l.22-.18s.03-.02.02-.04c0,0-.01,0-.03,0,0,0,0,.01,0,.03-.04,0-.1.04-.17.1-.07.06-.15.11-.23.15-.06.03-.12.07-.17.1l-.08.08v.03s0-.03,0-.03l.07.02h-.03s.01.07.01.07l.06-.04ZM40.71,57.58l-.08-.54-.04-.06-.02.07.02.09s0,.02.01.06c.03.04.04.07.02.09,0,.04,0,.08-.01.1.03.04.05.1.07.18,0,.02,0,.03,0,.03.02,0,.03,0,.03,0v-.03ZM39.88,57.4s.02-.03.05-.08v.06s.02.03.02.03c.02,0,.03-.02.02-.04-.03-.13-.04-.22-.03-.29,0-.18.02-.31.04-.4,0-.11.02-.28.05-.5l.04-.27v-.03s-.04.02-.03.04l-.12.49v.23s-.07.04-.07.04v-.06s.03-.27.03-.27c.01-.35.05-.61.12-.78,0,0,0-.01,0-.03,0-.02-.02-.04-.04-.06h-.03c-.07.11-.1.18-.12.23l-.09.48-.04.27c0,.18,0,.28,0,.33v.03s.04,0,.04,0c0-.02,0-.03,0-.03l.03-.3v.36c0,.09,0,.19.01.29,0,.11.02.24.05.38.02.1.05.19.09.24v-.36ZM46.9,61.05s0-.06.04-.11c-.02,0-.05.03-.08.08l.04.02ZM40.27,57.06s0-.07.05-.08c.05.01.06-.02.04-.11l.02-.04.04.02.02-.07s-.02-.05-.05-.09c-.01-.06-.01-.11,0-.13l-.04-.19.04-.14s-.06,0-.07-.02c.02-.03.02-.04.02-.04l.02-.2v-.03s-.04,0-.04,0v.03s0,0-.02,0c0-.02,0-.03.02-.04v-.06s-.03-.06-.03-.06c0,.02,0,.03-.02.04l-.05.24c-.06.34-.05.66,0,.95v.03s.03-.04.03-.04ZM40.31,56.52c.02-.09.04-.14.04-.14h-.03s-.04.15-.04.15l.04.02v-.03ZM40.62,56.75c-.01-.06-.01-.16,0-.29h-.06s.02.27.02.27v.03s.04,0,.04,0ZM46.75,60.66l.14-.13s-.03,0-.03,0c0-.02,0-.03,0-.03l-.14.13v.03s.04,0,.04,0ZM45.2,59.58s.03-.04.06-.04c.04,0,.07-.03.09-.05v.03s-.14.1-.14.1v-.03ZM40.4,55.85c-.01-.06,0-.14.01-.23v-.03s0,.03,0,.03l-.08.21.04.02h.03ZM48.08,60.3v-.03s-.02.04-.06.04c-.05-.01-.08,0-.09.02,0,.02,0,.03-.02.04l-.07-.02-.02.04c.05.03.08.05.08.05l.2-.14ZM39.64,54.77l-.07-.02-.07.15h.03s.1-.13.1-.13ZM40.53,55.13h-.03s-.04.11-.04.11c.02,0,.03,0,.04.02l.04-.14ZM48.33,60.11v-.03s-.07.01-.07.01l-.11.09-.02.04s0,.03,0,.03c.02,0,.03,0,.03,0l.17-.13ZM48.51,60.17c.06-.03.14-.11.25-.22l.02-.04s-.02-.03-.04-.02l-.33.27s-.03.03-.02.07h.06s.06-.06.06-.06ZM39.87,54.03h-.03s-.11.26-.11.26c.02,0,.03,0,.04.02l.1-.28ZM40.04,53.31v-.03s-.03.04-.03.04l-.08.21v.03s.12-.25.12-.25ZM41.21,53.74l.21-.41-.04-.02s0,.06-.02.07c-.06.03-.1.09-.13.16,0,.07-.03.13-.06.18v.03s.04,0,.04,0ZM40.95,52.68v-.03c.03-.05.05-.08.07-.08.06-.01.09-.05.07-.11v-.06s.21-.31.21-.31l.05-.08.08-.21c.05-.06.11-.15.16-.3.02,0,.03-.02.02-.04-.01-.06.03-.11.14-.13l.1-.15.12-.19v-.03s-.02,0-.04,0c0,0,0,.01,0,.03l-.09.18s-.02-.06-.04-.06c-.04,0-.05-.01-.01-.06,0-.04,0-.08.01-.1l-.09.05-.23.31c-.05.16-.14.35-.27.55l-.04.14c-.08.13-.12.19-.12.19l-.22.47-.04.14h.06s.07-.13.07-.13ZM41.95,50.83l-.04-.06-.02.04s.03.06.08.05v-.03ZM42.05,50.81s.06-.02.06-.04c0,0,.02-.04.07-.11l.17-.27s.02-.06.01-.1c.02-.03.01-.04,0-.03,0-.02,0-.03,0-.03l-.06.04-.02.07-.22.34-.04.11s0,.03,0,.03c.02,0,.03,0,.03,0ZM41.46,53.06s.03-.04.06-.04c.02,0,.04-.03.05-.08.04-.03.06-.07.07-.11.03-.07.06-.13.09-.18.04-.14.08-.27.14-.39.06-.14.11-.28.18-.4l.5-.86.29-.49.2-.44.16-.3.18-.24c.04-.1.1-.19.17-.27,0-.02,0-.03.02-.04.02-.03.01-.05-.01-.06h.03s.11-.1.11-.1l.22-.34s.03-.05.1-.15l-.04-.06-.02.04-.2.27-.47.69-.21.37-.24.41-.28.52-.09.18s-.04.05-.08.08c-.04.03-.06.06-.08.08l-.04.11-.19.34c-.13.29-.21.45-.22.47-.02.03-.07.15-.15.36l-.19.47-.07.11.04.02ZM42.49,50.12s.02-.06.01-.1h.03s.11-.26.11-.26h-.03c-.07.09-.1.17-.08.25-.07-.03-.1-.01-.09.05,0,.02,0,.03-.02.04l.07.02ZM44.07,48.5l.07-.11-.04-.02-.07.11v.03s.04,0,.04,0ZM44.13,48.35s0-.03,0-.03c.02,0,.03,0,.03,0,0,0,.07-.1.2-.3v-.03s-.04,0-.04,0l-.2.3v.03s.01.03.01.03ZM55.27,64.79l-.09-.11c-.06-.07-.1-.14-.11-.21-.12-.37-.2-.63-.24-.8h.03s-.15-.53-.15-.53v-.36c-.05-.17-.06-.28-.06-.35,0-.18,0-.29-.01-.36v-.06s-.04,0-.04,0c0,.02,0,.03,0,.03-.02.03-.02.06-.01.1-.01.05-.03.17-.05.37v.03s.02.11-.05.21v.3s0,.03,0,.03l-.04-.02v-.13s-.02-.06-.04-.06l-.04-.06-.02.07v.13s.03.06.07.05v.03s.19.68.19.68l-.02.04v-.03s-.22-.51-.22-.51l-.1-.31c-.05-.23-.05-.44,0-.62l.02-.07s0-.03.02-.04v.06s.01.1,0,.23l.04.06.04.02.08.05s-.01-.06-.01-.06v-.03c-.02-.06-.02-.13-.02-.19.03-.07.03-.13,0-.16.04-.03.05-.08.04-.14,0-.07,0-.12,0-.16.03-.07.04-.17.03-.3.02-.11.03-.2.04-.27,0-.26.03-.45.07-.57l.07-.28c.04-.23.05-.38.03-.47l-.02-.09c-.02-.08-.03-.18-.03-.29.02-.11.02-.19.01-.23,0-.04,0-.06.02-.07.01-.05.03-.11.06-.18.03-.07.05-.15.08-.25.03-.07.04-.14.02-.2,0-.07.01-.13.02-.2v-.03s-.04.06-.06.04c0-.02-.02-.03-.04-.02-.03.05-.05.09-.04.11-.01.05-.02.09-.04.14,0,.04,0,.09,0,.13-.05.08-.05.16,0,.26,0,.04,0,.07-.05.08l-.04-.02v-.06c0-.07,0-.14,0-.23,0-.11.01-.2.04-.27.07-.28.12-.51.15-.69.01-.13.03-.26.05-.37.04-.12.07-.23.09-.35l.02-.07v-.03s-.04,0-.04,0c-.05.06-.09.15-.1.28-.01.05-.03.09-.07.15-.02.03-.03.05-.05.08-.01.13-.01.23,0,.29l-.04.11s.02.03.04.02v.03s-.13.29-.13.29c-.03.07-.06.17-.1.28-.02.11-.03.2-.04.27l-.13.75-.06.47v.1s-.1.48-.1.48c0,.02,0,.02-.03,0-.02,0-.03,0-.04-.02l-.03-.16h.03c.05.03.07.01.06-.05-.01-.06-.01-.11,0-.13-.02-.08-.02-.21-.02-.39v-.03c-.02-.06,0-.17.06-.31l.04-.11s0-.04.02-.07c.01-.05.03-.07.05-.08.02,0,.03-.03.02-.07v-.03c-.03-.08,0-.2.05-.34,0-.26.05-.53.12-.81.04-.14.05-.22.05-.24l.02-.36c0-.07.01-.14.01-.23,0-.11.01-.19.05-.24,0-.07,0-.13,0-.19,0-.09.02-.16.05-.21v-.06c-.06,0-.07.02-.07.04-.02,0-.03.02-.02.04.02.1.01.2-.03.3-.04.1-.07.17-.08.21l-.03.17c.02.08,0,.13-.07.15-.06.01-.08.06-.07.15,0,.02,0,.04-.02.07-.02.03-.03.04-.06.04l-.04.11c-.1.72-.21,1.28-.32,1.68l-.12.49s0,.03-.02.04l-.04-.02s-.03-.07-.05-.09c.01-.13.04-.24.06-.31.02-.29.04-.48.04-.57v-.03s-.03.04-.03.04l-.07.28c-.08.13-.14.27-.17.43,0,0-.01,0-.03,0,0,0,0,.01,0,.03v-.03s-.05-.06-.05-.06v.06c-.03.12-.07.29-.1.52l-.06.04s.02-.02,0-.03c0,0,.01,0,.03,0,.01-.13.01-.23,0-.3.03-.07.04-.2.05-.37v-.03c.04-.08.07-.17.06-.28.01-.13.03-.22.04-.27v-.06s-.03-.06-.03-.06l-.06.04c0,.11-.03.26-.1.45-.01.05-.02.09-.04.14-.02.03-.03.06-.04.11-.03.05-.05.08-.05.08l-.02-.09.07-.28c0-.07.01-.13.02-.2,0-.09,0-.17.01-.23l.05-.21c.03-.05.03-.08-.02-.09-.02,0-.03,0-.03,0,0-.02,0-.03,0-.03l.07-.28v-.03s-.04,0-.04,0l-.04.11-.02.04v-.06s.02-.16.04-.34l.25-1.1.15-.95c.03-.07.04-.16.04-.27.01-.13.03-.23.03-.3.07-.28.11-.49.12-.65.02-.11.05-.24.08-.38.05-.16.08-.3.07-.41.12-.46.2-.81.23-1.03.08-.32.14-.62.17-.89,0-.13,0-.26.04-.4.05-.16.08-.28.09-.35l.21-1.16.16-.62s.02-.09.04-.14c0-.07,0-.13,0-.19.12-.46.17-.8.17-1.02l.06-.31c0-.07.02-.15.05-.24.02-.11.03-.22.03-.33l.19-.93c.01-.13.09-.4.22-.8.02-.22.03-.35.05-.37.03-.07,0-.1-.08-.08l-.25.05c-.41.13-.72.24-.94.34-.32.11-.59.22-.79.3-.31.09-.68.26-1.1.5-.24.12-.44.24-.61.36-.17.1-.32.19-.44.26l-.96.57s-.03.05-.05.08c-.17.04-.32.11-.47.23-.13.12-.23.2-.3.26-.14.16-.25.27-.32.33-.03.05-.05.08-.05.08-.02.03-.05.04-.09.05.02,0,.03-.03.02-.07l.23-.31.37-.41s.04-.05.08-.08c.04-.03.05-.06.05-.08l.18-.24.02-.04.46-.46.11-.09s.05-.03.08-.08c.02,0,.03,0,.03,0,0-.02,0-.03,0-.03h.06s.08-.04.12-.07c.03-.05.07-.09.1-.12v-.03s-.04,0-.04,0l-.27.09-.07-.02v-.06s.3-.36.3-.36l.02-.07.22-.18v-.03s-.04,0-.04,0h-.06s0,.02,0,.04c0,0-.01,0-.03,0l-.08.08s-.01,0-.03,0c0,0,0-.01,0-.03-.04,0-.06.01-.06.01l-.32.17s-.09.05-.15.07h-.03s.02-.06.02-.06l.12-.06.07-.11.02-.04c.1-.06.23-.18.41-.35h.03c.08-.02.14-.05.18-.08.03-.05.15-.12.35-.21l.09-.05s.03-.07.05-.08c.06-.01.12-.04.18-.07.05-.06.12-.09.21-.11h.03s.06-.02.06-.02c.02-.03.03-.04.06-.04.04,0,.07-.03.09-.05.02,0,.06-.04.1-.12.03-.05.06-.07.09-.05,0,.02,0,.03,0,.03.02,0,.03-.02.02-.04l.07-.11s-.02-.03-.04-.02l-.24.09-.75.33s-.07.04-.14.1h-.03s.02-.03.02-.03l.14-.1.02-.07s-.03.04-.06.04l-.09.02s-.06-.02-.1-.01l-.47.23h-.03s.02-.03.02-.03l.35-.21.33-.14.02-.04h-.03s-.04.02-.06.02c0-.02-.01-.02-.03,0-.06.01-.11.04-.15.07h-.06s.06-.03.06-.03c.19-.13.34-.22.44-.26l.06-.04h-.06c-.1.04-.19.06-.24.1-.06.03-.13.06-.21.08-.08.02-.14.04-.18.07-.06.03-.15.07-.27.09v-.03s.38-.18.38-.18c.02-.03.03-.04.06-.04.04,0,.07-.03.09-.05.13-.12.31-.23.55-.35.35-.19.57-.3.65-.34.02,0,.03-.02.02-.04h-.06c-.06.05-.14.1-.26.17-.1.04-.2.07-.31.07-.03-.02-.05-.01-.06.01,0,0-.01,0-.03,0l.08-.08.11-.09c.15-.12.32-.21.53-.28.2-.09.33-.15.39-.18l.35-.18.09-.05c.07-.06.14-.1.21-.11.24-.12.37-.19.41-.22l.15-.07.16-.03h.06s.09-.07.09-.07h-.1s-.42.02-.42.02l-.02.04.02-.04.41-.09.19-.04.02-.04s.05-.08.11-.09c.1-.06.24-.14.44-.23l.52-.18c.19-.11.49-.25.89-.42.12-.07.34-.16.66-.27.1-.06.22-.13.39-.18.16-.08.28-.14.35-.18.34-.16.64-.28.9-.36.12-.05.23-.09.33-.14.12-.07.23-.13.35-.18.1-.02.22-.06.34-.11.12-.07.24-.12.36-.14l.41-.06c.09,0,.18-.02.28-.06l.2.02.17.03h.06c.1.03.21.05.34.04s.22-.01.26-.02c.04,0,.16,0,.36.02.2.02.37.08.5.19.09.09.29.22.61.39.09.02.18.06.25.11.08.05.15.09.22.12,0,.02.03.05.08.08.08.05.12.12.14.2l.03.13c.01.06-.01.09-.08.08-.03-.02-.05.01-.08.08-.03.05-.04.1-.04.14,0,.04,0,.09,0,.13,0,.04.03.08.06.12.09.11.14.2.16.26.02.08.04.14.07.18,0,.02.06.12.16.29.01.06-.03.11-.14.13l-.48-.09c-.06.01-.11.04-.15.07-.06.01-.1,0-.1-.01-.29-.13-.53-.2-.73-.2-.09-.02-.25-.01-.48.04-.23.03-.49.11-.77.23-.28.11-.48.18-.6.23l-.98.44-.54.25-.09.02.08.05.13.17c.05.03.08.05.08.05.18.11.24.26.2.45l.04.02c.03.06.04.11,0,.16-.04.03-.06.06-.08.08,0,.02,0,.03-.02.04-.02,0-.03,0-.03,0l-.25-.08-.09.02s-.03.03-.02.07c-.03.07-.11.14-.25.22-.02,0-.06.04-.1.12-.01.05-.07.23-.17.56-.11.2-.2.48-.27.85l-.24,1.17-.27,1.01-.21.83c-.03.25-.07.47-.11.68-.05.18-.09.36-.12.52-.12.44-.18.71-.19.79-.01.05-.02.1-.03.17,0,.07-.01.13-.02.2l-.11.38c-.04.21-.07.34-.07.41l-.09.48-.15.69-.23.77c-.04.21-.09.39-.14.55-.03.16-.06.31-.1.45l-.3,1.02c-.04.31-.1.59-.18.83-.08.41-.14.72-.16.92,0,.07,0,.15,0,.26,0,.09-.02.2-.06.34-.02.11-.05.24-.08.38-.03.16-.06.32-.09.48l-.35,1.39-.05.53-.1.61c-.05.47-.06.8-.01.99l.18.98.17.49s0,.03-.02.04v-.03s0-.01-.01-.03c0,0,0,.01-.02.04v-.03s-.04.02-.03.04l-.02.07-.04-.06ZM54.25,61.35c.05-.18.07-.32.07-.41l.06-.04c-.03.07-.06.22-.1.45l-.02.07v-.06ZM54.38,60.89c-.01-.06-.03-.1-.06-.12l.02-.07.04.06v.13ZM54.89,58.39l.07-.15-.04-.06s0,.03-.02.04l-.03.17v.03s.03-.04.03-.04ZM49.7,47.34s.06-.03.05-.08c.06-.01.1-.03.12-.06h.03s.18-.24.18-.24c.05-.08.15-.13.29-.16l.07.02h-.06s-.14.14-.14.14c0,.07-.04.11-.1.12-.04,0-.09.05-.14.13l-.21.11s-.03.04-.06.04c0-.02-.02-.03-.04-.02ZM50.87,46.4c.03-.05.06-.08.08-.08l-.04-.02-.08.08.04.02ZM50.92,45.3h.03s.24-.12.24-.12h.03s-.02.03-.02.03c-.06.03-.14.06-.24.09h-.03ZM64.08,59.63l-.12-.24c-.02-.08-.05-.13-.1-.14v-.06s-.08-.31-.08-.31c.01-.13.01-.23,0-.29,0-.04-.05-.08-.12-.1-.02,0-.04,0-.07-.02,0-.02,0-.04-.01-.06v-.06c-.03-.06-.02-.13,0-.2.03-.05.05-.1.07-.15,0-.07.05-.26.13-.59.05-.18.07-.33.07-.44h.03s.06-.05.06-.05c0-.04,0-.11.02-.2l.09-.64v-.03c.03-.05.04-.09.04-.11.01-.05.02-.08.01-.1l.05-.37v-.26s0-.03,0-.03c0,0-.01,0-.03,0,0,0,0,.01,0,.03l-.07.28s-.01,0-.03,0c0,0,0,.01,0,.03v-.03s-.02-.06-.02-.06l-.02.04h-.03s0-.02,0-.02l.07-.28.08-.38c.02-.09.03-.15.03-.17l.11-.42-.05-.09-.05.08-.04.11-.02-.09v-.03s0,.03,0,.03c-.07.19-.11.31-.12.35-.03.05-.07.14-.11.25-.04.1-.07.19-.07.28l-.05.08v-.06c.01-.18.03-.28.05-.31.04-.14.05-.26.05-.37.02-.11.04-.22.06-.31.02-.09.03-.16.02-.2v-.03s0,.03,0,.03h-.03s-.02.08-.02.08v-.06s-.03-.06-.03-.06v-.03s-.04.02-.03.04c-.02,0-.03.02-.02.04v-.06s-.02-.16-.02-.16c0-.02-.02-.03-.04-.02,0,0-.01,0-.03,0,0,0,0,.01,0,.03-.03.07-.05.17-.06.31l-.11.38-.16.62-.34,1.32c-.04.1-.07.19-.07.28,0,.07-.02.12-.03.17-.03.05-.04.1-.04.14l-.12.52s-.02.06-.01.1h-.03s-.01,0-.03.01c0-.02,0-.03.02-.04.04-.34.07-.55.09-.64l.24-1.13.26-1.2-.02-.09-.02.07-.04.11-.17.59c0,.07-.05.26-.13.59v-.03s.04-.24.04-.24v-.13s0-.03,0-.03c-.04,0-.05.01-.03,0,.02-.03.02-.05.02-.07l-.05-.25-.13.29s-.03.03-.02.07c-.03-.02-.04-.05-.05-.09,0-.04,0-.11.02-.2l.09-.51s0-.11,0-.19l.05-.21v-.03s-.04,0-.04,0l-.1.32-.06.04s-.03-.03-.07-.02c-.03-.02-.03-.04-.01-.06l.11-.42.23-1.06.09-.35v-.06s-.07.04-.07.04l-.05.24s0,.03-.02.04v-.03s-.02-.06-.02-.06h-.03c-.02.1-.05.17-.08.22v-.03s.06-.31.06-.31c.01-.05.03-.16.06-.34l.12-.65.18-.99c.07-.28.11-.48.13-.62l.2-.89.14-.88.22-.96.25-1.43.12-.81.27-1.63c.06-.43.13-.77.2-1.03.03-.07.09-.29.18-.66l.12-.35.11-.42c.03-.16.12-.27.26-.32.02,0,.05-.02.09-.05.03-.05.07-.08.11-.09.1-.06.17-.09.21-.08.02,0,.05,0,.1.01.04,0,.09-.03.15-.07.03-.05.08-.05.13,0,.07,0,.13,0,.19-.04l.21-.08c.08-.02.17.02.25.11l.07.02c.08.07.16.1.25.08.1-.04.17-.07.21-.08.2,0,.35.03.45.1.19.09.37.2.53.34.15.1.23.15.23.15.03.02.1.04.21.08l.08.05.2.15c.13.08.13.15,0,.19-.08.04-.14.12-.18.24-.02.09-.08.14-.17.13-.1.02-.16.07-.17.13,0,.02-.01.04-.06.04h-.13c-.06,0-.11,0-.13,0-.09,0-.15.03-.17.1-.15.23-.25.47-.3.72-.04.12-.08.27-.13.45-.05.16-.1.36-.13.59l-.23,1.03-.14.85-.14.72s-.03.09-.05.21c0,.11-.03.2-.1.28-.02.03-.02.07,0,.13-.04.12-.07.19-.08.21-.03.05-.07.17-.12.35l-.15.66-.13.59-.15.69-.13.59c-.08.26-.17.64-.28,1.14l-.23.9-.18.69-.13.62c0,.09-.01.2-.03.33-.01.13-.05.29-.09.48,0,.09-.02.19-.06.31-.02.09-.04.21-.06.34l-.19.93-.1.32v.16s-.04.27-.04.27l-.06.18v.03c-.04.08-.08.18-.12.32-.04.14-.07.24-.1.32l-.09.35c-.08.24-.11.47-.08.7l.04.06c.07,0,.08.04.05.09-.04.12-.05.23-.03.33,0,.11-.03.25-.11.42.01.06.01.11,0,.13l-.02.07-.04-.06ZM63.35,58.09v-.03s.01-.07.01-.07l.04.06v.03s-.04.11-.04.11l-.02-.09ZM63.88,58.24l-.03-.13v-.06s-.03-.06-.03-.06l-.02.07s0,.11,0,.19l.04.06.02-.07ZM63.94,58.22s.02.03.04.02c.02,0,.03-.02.02-.04.04,0,.06-.03.05-.08,0-.02-.04-.07-.1-.14l-.04.14-.02.04s.02.06.04.06ZM63.56,57.85c.01-.13.03-.26.05-.37l.02-.04s0,.03,0,.03c.03.02.03.04.01.06-.02.03-.02.06-.01.1.01.06.01.12,0,.16,0,.04,0,.11-.02.2h-.03s-.03-.15-.03-.15ZM64.15,58.01s.03-.02.02-.04l.02-.2s0-.06.02-.07l-.04-.02-.04.11v.03c.02.06.02.12,0,.16v.03ZM63.38,57.59s0-.1,0-.16c.02-.09.04-.16.05-.21l.09-.51s0-.11,0-.19l.02-.04v.03s.01.03.01.03c.02,0,.03,0,.03,0,.04,0,.06,0,.04.06l-.09.35s-.03.02-.02.04l.04.06s0-.03.02-.04v-.06s.02,0,.02.02c0,.04,0,.08-.01.1l-.08.25v.06s.02.01.02.03c0,.02.01.02.03,0v.03s-.12.16-.12.16c0,.02,0,.03-.02.04l-.02.04v-.06ZM63.74,56.56l-.04.27h-.03s.07-.27.07-.27ZM64.32,57.26s.03-.02.02-.04l.09-.35h-.03s-.12.36-.12.36c.02,0,.03,0,.04.02ZM63.79,56.78s-.02-.03-.04-.02l.09-.35s.03-.02.02-.04v.03s-.08.35-.08.35v.03ZM63.78,56.29v-.03s0,.03,0,.03c.02,0,.03,0,.03,0l-.07.28.04-.27ZM63.63,55.9s0-.08.01-.1l.07-.11v.03s-.01.07-.01.07l-.04.11v.03s-.03-.02-.03-.02ZM63.8,56.09s.02-.06.01-.1l.05-.21.05-.08.02.09-.1.32h-.03s0-.02,0-.02ZM63.65,55.4s0-.06.04-.11c0-.02,0-.03.02-.04v.03s-.04.11-.04.11c0,.02,0,.03-.02.04v-.03ZM64.18,55.12s0-.03,0-.03c.02,0,.03,0,.03,0l.05-.24v-.03s-.02,0-.04,0c0,0,0,.01,0,.03l-.06.18.02.09ZM63.65,54.36s.02-.05.02-.07c0-.04,0-.08.01-.1l.02-.04v.06s-.02.14-.02.14c0,0-.01,0-.03,0,0,0,0,.01,0,.03v-.03ZM64.27,54.02s.02-.07,0-.13c-.03.05-.05.09-.04.11v.03s.04,0,.04,0ZM65.47,52.78l.09-.18v.03s-.06.15-.06.15c0,.02,0,.03-.02.04v-.03ZM72.99,55.4c-.06.01-.13.02-.19,0-.05-.01-.1-.01-.16,0-.05-.01-.1,0-.16.03-.06.01-.14.02-.23.02l-.4-.04h-.06c-.04-.07-.1-.12-.2-.14-.09-.02-.16-.05-.21-.08-.09-.02-.17-.05-.25-.08-.06-.05-.12-.08-.18-.09-.03-.04-.07-.07-.12-.1-.05-.03-.1-.08-.16-.13l.07.02-.5-.51c-.15-.17-.29-.47-.43-.92l-.17-.16s-.04-.03-.04-.06c.01-.05.02-.08.01-.1-.11-.32-.18-.54-.21-.64-.06-.27-.1-.49-.11-.66.09.2.14.35.16.46h.03c-.03-.15-.1-.35-.19-.59h-.03s0,.08-.01.11c-.06-.1-.12-.26-.17-.49-.05-.25-.09-.45-.1-.6,0-.13-.02-.45-.05-.97,0-.07,0-.17,0-.29,0-.15,0-.27-.01-.36-.01-.06-.04-.12-.07-.18-.02-.08-.03-.17-.02-.26.04-.53.1-.97.2-1.32.06-.21.09-.47.09-.77.02-.09.05-.18.07-.28.04-.12.08-.25.11-.38.02-.09.03-.19.03-.3.01-.13.04-.26.08-.38.04-.23.07-.38.1-.45.01-.05,0-.11,0-.19v-.03s.21-.64.21-.64l.26-.45c.11-.29.18-.47.21-.54.08-.15.17-.29.27-.42.12-.14.22-.28.3-.43l.4-.55c.15-.23.29-.38.43-.45.45-.36.78-.61,1.02-.75l.18-.2c.09-.09.23-.15.42-.19l.65-.17c.13-.03.21-.13.26-.32l.05-.24.02-.04h.03c.06-.02.12,0,.18.05.07.03.12.07.16.13l.13.14c.04.08.1.14.17.19.08.05.14.09.19.12.02,0,.03,0,.04.02-.03.05-.02.11.04.19,0,.04.04.1.1.17l.02-.04s0-.12-.02-.23l.06-.04.54.08c.09,0,.16-.01.22-.05.02-.03.05-.04.09-.05.06-.01.11-.01.13,0,.05.01.09.02.14.04l.04.02c.13-.03.14,0,.05.09h.36c.18.03.32.08.39.13.15.1.24.17.27.2.03.06.09.11.17.16.08.05.14.09.19.12l.03.12c.12.06.22.09.28.1.07,0,.13-.03.17-.1.02.1.06.17.11.21.07.03.12.05.15.07.09.02.15.07.16.13,0,.04.02.07.02.09l.05.09c.2.24.34.52.41.83l.17.65c.07.33.11.83.13,1.48l-.02.82c-.02.31-.02.54-.01.69v.36s0,.07,0,.07l-.03-.13-.08.25c-.02.11-.05.27-.09.48-.03.18-.08.4-.15.66-.22.59-.37.97-.44,1.14-.08.26-.17.48-.28.68l.02.09s.06-.02.06-.04c.02,0,.07-.04.14-.1-.04.14-.09.23-.17.27-.22.11-.35.31-.4.58,0,.13-.04.3-.15.52-.52.81-.78,1.22-.78,1.22,0,0-.21.33-.64.99-.02.03-.02.06-.01.1,0,.02,0,.04-.02.07l-.06.18-.08.38c-.08.15-.18.18-.31.1l-.15-.07-.06.04c-.21.42-.34.68-.39.77l-.05.21-.08-.05s-.02.03-.05.08l-.07.15h-.13s-.1.07-.18.2c0,.02-.01.04-.06.04-.02,0-.03,0-.03,0-.06-.05-.11-.06-.17-.03-.06.03-.11.06-.15.07-.16.08-.31.11-.47.1-.02,0-.07.02-.16.03-.06.01-.11.05-.14.1-.04.03-.1.05-.18.07l-.57.09ZM69.92,52.89s-.04-.07-.1-.14h-.03c.08.06.12.1.13.14ZM71.86,53.85s.03-.03.03,0c.02,0,.04,0,.06-.01l.39-.18c-.05-.03-.09-.05-.11-.04-.04,0-.1.02-.19.04-.09,0-.16.01-.22.05-.04.03-.11.06-.21.08-.09,0-.16.01-.22.05-.04,0-.1.01-.16,0-.05-.01-.07.02-.08.08h-.03c-.09,0-.22-.02-.41-.07l-.28-.1c.06.07.14.12.23.15,0,.02.02.05.05.09.03.02.05,0,.09-.05.03.04.07.05.11.04.06-.01.1-.01.1.01.03.02.06.02.1.01l.32-.04-.08-.05.33.03.18-.07ZM72.02,54.11c-.05-.03-.1-.04-.14-.04v.03s.14,0,.14,0ZM70.6,53.01l-.18-.06c.06.05.1.09.12.1h.06s0-.04,0-.04ZM70.26,53.08v-.06s.02,0,.02.02c.02,0,.04,0,.07.02-.04-.08-.11-.15-.21-.22-.08-.07-.12-.14-.11-.21l-.08-.08s-.02-.03-.04-.02c-.01-.06-.03-.1-.06-.12l.14.04c-.09-.09-.13-.14-.13-.14-.06-.1-.13-.2-.2-.32h-.03s-.04-.03-.04-.05c0-.04-.03-.07-.05-.09l.02.09v.03s.08.02.08.02c-.02.03-.02.07,0,.13.01.06.06.17.14.33.02.1.05.16.07.18.1.15.23.3.39.44h.03ZM71.64,53.57c.1-.02.19-.03.26-.02v-.03s-.59-.1-.59-.1l.39.28-.06-.12ZM71.07,53.36l.07.02c.15,0,.24,0,.26-.02.06-.03.11-.05.16-.03.07,0,.12,0,.16-.03.04-.03.1-.05.18-.07.08-.02.14-.04.18-.07l.07.02.14-.1.11-.09v-.03s.04-.03.07-.08l-1.51.43-.04-.06s0,.03,0,.03l-.72-.14s.09.06.27.17c.05.03.1.05.15.07.07,0,.12.02.17.03l-.12.06.11.04.12-.03h.23s-.06-.1-.06-.1ZM72.05,53.35s.07,0,.06-.01c0-.04-.02-.07-.02-.09l-.17.1h.13ZM71.83,54.31c.06-.01.15-.02.26-.02.13-.03.22-.06.27-.09.7-.3,1.2-.69,1.52-1.15l.04-.14-.08.08h-.03c-.05.06-.11.12-.16.17-.03.05-.07.1-.1.15-.08-.05-.09-.02-.05.08-.02,0-.04,0-.06.01-.03-.02-.05-.01-.06.01l-.35.21-.02.07c-.06.01-.11.04-.15.07-.04,0-.1.04-.17.1l-.25.19c-.08.04-.15.07-.21.08-.05-.01-.09-.01-.13,0h-.03c-.06.02-.1.04-.12.07h-.06s-.06.06-.06.06l-.05-.09s-.05.03-.08.08c-.02.03-.05.02-.1-.01,0-.02-.01-.02-.03,0,0,.04.02.06.04.06.09.02.17.03.23.01ZM73.07,53.39v-.03c-.06.03-.12.07-.18.1-.04.03-.07.06-.11.09v.03s.29-.19.29-.19ZM72.19,53.25c.2-.09.36-.14.49-.17-.13-.01-.23-.01-.29,0h-.03c0,.09-.06.13-.17.11l-.06.04.07.02ZM72.78,52.93s.02,0,0,0c0-.02,0-.03,0-.03-.04,0-.07.03-.09.05l-.06.04s.06-.01.06-.01l.09-.05ZM72.55,52.78c.23-.14.5-.27.8-.4v-.03s-.81.37-.81.37v.06ZM73.35,52.7l-.04-.02s-.05.03-.08.08h.03s.09-.06.09-.06ZM74.12,52.77s-.04-.02-.04-.02c.02-.03.01-.05-.01-.06l-.07-.02c-.07.1-.1.15-.1.15l.16-.03h.06ZM75.59,53.52h-.03s-.05.04-.08.09c.02,0,.03,0,.04.02l.07-.11ZM73.42,52.29s.07-.04.14-.1v-.03s-.14.13-.14.13ZM74.13,52.7s0-.06.04-.11l-.07-.02-.02.07.04.06ZM73.33,52.15s.07-.04.14-.1l-.04-.02-.1.12ZM76.18,53.99c.03-.05.06-.08.08-.08,0,0,.03.02.08.05l-.16.03ZM74.19,52.52s.05.04.07.02c.04-.03.07-.05.09-.05l-.11-.04-.09.02.04.06ZM73.74,51.93c.07-.06.19-.16.36-.31v-.03s-.39.35-.39.35h.03ZM74.37,51.69s-.03,0-.03,0c0-.02,0-.03,0-.03l.4-.41v.03s-.36.41-.36.41ZM72.57,53.49c.06-.03.14-.07.24-.12.1-.06.19-.13.29-.19.28-.21.5-.41.66-.6l.23-.28.19-.17.3-.43c.16-.17.26-.29.31-.36l.49-.63.28-.39s.12-.19.37-.57c.04-.03.05-.06.05-.08,0-.02,0-.04.02-.07.1-.15.15-.23.15-.23.05-.08.09-.14.12-.19.03-.07.06-.13.09-.18-.13.03-.2.1-.22.21,0,0,0,.01,0,.03,0,0-.01,0-.03,0,0,.04-.03.16-.12.35l-.14.13-.14.13v-.03s-.04.17-.04.17l-.04-.06-.07.11s.03.03.07.02c-.03.05-.06.07-.09.05-.04,0-.09.05-.14.13-.03.05-.05.09-.04.11v.1s-.07.01-.07.01c.02,0,.03,0,.03,0,0-.02,0-.03,0-.03-.03-.02-.07.02-.14.1-.05.08-.09.14-.12.19-.03.07-.06.12-.1.15-.04.03-.06.06-.08.08l-.12.19h-.06c-.19.25-.35.42-.48.51-.06.03-.12.1-.18.2v.03s.26-.19.26-.19c0,.02,0,.03,0,.03.02,0,.03,0,.03,0l-.83,1c-.13.12-.28.23-.45.36-.17.12-.35.26-.53.41.03.02.05.01.06-.01ZM74.15,51.58c.11-.09.21-.2.29-.33h-.06s.1-.11.1-.11c.02-.03.03-.04.06-.04.04-.03.05-.06.05-.08l.14-.13s-.02-.03-.04-.02l-.1.15c-.12.07-.19.13-.22.18v.06c-.06.06-.13.1-.19.11l.04.06.17-.13c-.11.11-.18.2-.23.28ZM74.87,51.1s-.05.04-.09.05h-.03s0-.02,0-.02l.05.09.07-.11ZM75.48,51.52s.05-.1.13-.16h-.03s-.03.05-.06.05c-.02,0-.04.03-.05.08v.03ZM74.86,51.06s.03-.04.06-.04c.04-.03.06-.07.07-.11.02,0,.03,0,.04.02l-.14.13h-.03ZM74.94,50.52c.15-.12.25-.22.3-.29-.02,0-.03,0-.03,0,0-.02,0-.03,0-.03l-.25.35-.18.24s.02.03.04.02l.13-.29ZM76.36,50.9h-.03c-.11.18-.17.27-.17.27h.03s.17-.27.17-.27ZM74.15,52.79c.06-.01.1-.03.12-.06.16-.17.31-.35.44-.55.09-.09.2-.2.32-.33.12-.16.23-.29.34-.4l.06-.04.04-.14.28-.36.19-.34.46-.75.24-.41.04-.14.09-.18.1-.32c.09-.19.14-.34.17-.43v-.06s-.08.01-.08.01l-.04.14-.4.87c-.04.1-.1.2-.16.3-.04.1-.09.19-.13.29-.03.05-.07.12-.12.22-.03.07-.08.15-.15.23-.01.05-.05.1-.13.16l.04.02s0,.08-.01.1c-.1.15-.19.27-.28.36l-.16.17s-.01,0-.03,0c0,0,0,.01,0,.03l.07.02-.05.08c-.03.05-.09.11-.16.17-.05.06-.12.12-.18.2l-.35.5s-.18.21-.5.57l-.05.08ZM74.87,51.58l.3-.43s.18-.24.58-.78l.36-.6s.05-.08.04-.14l.2-.27.09-.18.04-.14s.03-.05.05-.08c.02-.03.03-.05.05-.08l.06-.18s.06-.11.22-.47v-.06s-.07.04-.07.04l-.21.37c-.11.29-.19.47-.24.54-.03.07-.08.18-.16.33-.06.14-.12.26-.19.34,0,0-.25.39-.76,1.18l-.42.62h.06ZM76.98,50.27v-.03s-.35.53-.35.53l.07.02.28-.52ZM77.21,49.51l-.06.04s.03.07.05.09v-.13ZM76.39,48.9l-.08-.05-.07.11s.02.03.04.02l.11-.09ZM76.89,49.41l.12-.22h.03s-.12.21-.12.21h-.03ZM76.07,49.1c.08-.13.18-.31.3-.56,0,0,0-.01,0-.03,0,.02,0,.03-.02.04-.09.11-.19.28-.31.53v.03s.04,0,.04,0ZM71.58,51.94c.08-.04.22-.13.44-.26.04-.03.07-.06.11-.09.06-.03.11-.06.15-.07.21-.05.41-.13.6-.26.19-.15.31-.24.37-.28.19-.11.34-.23.45-.36l.52-.64.41-.52s.01.05.02.09c.03.04.03.08,0,.13-.01.05-.03.09-.07.15-.02.03-.03.06-.04.11l-.18.37c.06-.01.11-.05.14-.1l.12-.22s.04-.08.07-.11c.06-.03.1-.05.12-.06.11-.09.19-.17.24-.25.07-.1.13-.19.2-.27l.13-.29c.05-.08.1-.19.16-.33.03-.07.08-.15.15-.23.07-.1.09-.2.06-.31h.03s.09-.19.09-.19l.29-.62c.08-.24.17-.43.27-.58.01-.05.02-.1.03-.17,0-.07.04-.12.1-.15v-.06s0-.1,0-.1l.02-.04-.04-.02s-.01-.06-.01-.06l.16-.3-.17.1c.03-.05.08-.1.13-.16.05-.06.08-.12.09-.18,0-.02,0-.03,0-.03.02,0,.03,0,.03,0l.02-.04-.07-.02s-.01,0-.03,0c0,0,0-.01,0-.03v-.03s.02-.04.02-.04c.09,0,.12-.04.1-.12,0,0,0-.07.02-.2,0-.02,0-.03,0-.03v-.1c.03-.13.04-.29.04-.47.02-.33.02-.56.01-.69-.01-.26-.04-.44-.08-.54,0-.04-.01-.1,0-.16,0-.07-.03-.13-.1-.17v-.03c.03-.05.03-.08,0-.1-.03-.02-.06-.02-.1-.01l-.34.07.07-.11-.09.02h-.03s-.55.19-.55.19c-.02,0-.07.03-.15.07-.06.03-.12.01-.18-.06h-.03s-.06,0-.09.03c-.04,0-.09,0-.13,0-.15.03-.26.09-.35.18l-.22.18h.13c-.19.15-.29.25-.33.3l-.06.04c-.07.17-.14.28-.19.34l-.15.2-.29.19.04.06.27-.12c-.03.05-.06.08-.08.08-.06.03-.14.09-.26.16-.1.04-.18.09-.23.15-.02.03-.09.09-.22.18-.12.07-.19.18-.22.34l-.09.05s-.07,0-.08-.05c-.02-.08-.04-.14-.07-.18,0,0-.01,0-.03,0,0,0,0-.01,0-.03-.08.02-.16.07-.23.15-.05.08-.08.13-.1.15-.03.05-.06.08-.08.08-.02,0-.04.02-.06.04-.02.03-.02.05-.02.07-.02.09-.05.18-.07.28-.03.07-.05.15-.08.25-.26,1.02-.41,1.63-.45,1.83-.05.18-.12.64-.23,1.36,0,.09-.01.19-.03.3-.02.11-.03.19-.05.24v.56s.06,1.39.06,1.39c.01.06.05.12.1.17.07.03.14.02.19,0ZM77.24,49.99c.07-.17.15-.33.22-.47.09-.17.18-.34.25-.51h-.03c-.06.13-.14.28-.23.45-.08.15-.16.32-.25.51l.04.02ZM77.32,49.58c.07-.1.12-.17.15-.2-.02,0-.03,0-.04-.02-.06.03-.1.11-.12.22ZM76.52,48.61s-.05-.02-.07-.02c0-.02,0-.03,0-.03,0,0-.02.03-.05.08,0,.04.03.06.08.05l.05-.08ZM75.57,51.63l.06-.04.48-.66v-.1s.09-.08.09-.08c.02-.03.01-.04,0-.03l.06-.04v-.13s.03.13.03.13c.03-.07.07-.15.12-.22.05-.08.07-.15.05-.21.04,0,.08-.04.11-.09.07-.06.16-.19.24-.38.04-.1.1-.21.16-.33s.12-.26.18-.4c.05-.08.04-.12-.03-.12l.02-.04.28-.68c.1-.33.17-.52.2-.57h.03c0,.06-.04.13-.08.21.09.02.15-.01.17-.1.04-.12.07-.23.09-.35.01-.13.04-.26.08-.38.03-.18.05-.29.06-.34,0-.02,0-.06.04-.11l.02-.2c.04-.23.04-.38,0-.46,0-.02,0-.03.02-.04.05-.16.05-.27,0-.33.02-.09.03-.16.02-.2l-.11-.04-.04.11c.02.19.02.43,0,.72h-.03s0-.12,0-.12c-.03.05-.06.08-.08.08l.04-.27s0-.12-.02-.23c-.1.06-.14.11-.14.13l-.13.45c0,.2-.01.4-.03.6l.02.09.09-.18.02.09.05-.08s0,.08-.01.1l-.05.24c-.03.07-.06.14-.08.21,0,.07-.02.14-.05.21-.02.09-.07.19-.13.29-.32,1.16-.79,2.22-1.43,3.19.03.02.06.02.1.01l-.06.04h-.03s-.09.06-.14.13c-.05.06-.08.1-.07.15v.03s.02.06.02.06h-.06s-.01-.05-.01-.05l-.12.19.07.02-.06.04-.02.07-.08-.05-.09.18h.03s.03-.01.03-.01c.02-.03.03-.04.06-.04l-.02.07h.03s.04-.15.04-.15ZM76.43,50.75l.2-.27s.04-.07.07-.15c.04-.1.1-.15.16-.17.02,0,.03-.02.02-.04.02-.03.03-.04.06-.04v-.03s-.09.05-.09.05c0,0-.01,0-.03,0,0,0,0-.01,0-.03.05-.06.14-.17.25-.35v.03s-.13.26-.13.26l.07.02.21-.41s0-.04-.01-.06c.01-.05.03-.09.07-.15,0,0,.07-.1.2-.3.08-.21.13-.32.13-.32l.22-.51.06-.18-.12.06.16-.46.08.05c.09-.28.17-.54.23-.77.06-.23.11-.44.16-.62,0-.02-.02-.03-.04-.02,0,.04,0,.07-.05.08v-.13s.14,0,.14,0l-.09-.11v.03s-.03-.19-.03-.19c-.02.03-.03.05-.05.08,0,0,0,.01,0,.03l-.16.62-.31,1.12-.03.17-.16.3-.34.83c-.04.1-.09.18-.14.26-.05.08-.09.15-.12.22l-.39.77-.19.34h.03ZM77.17,48.89s.06-.02.06-.04l.34-.83v.06s.08-.15.08-.15l.02-.07-.09.02-.06.04-.02.07c-.04.14-.14.42-.31.85,0,0,0,.01,0,.03,0,0-.01,0-.03,0ZM73.22,46.25c-.03-.34-.04-.6-.04-.78,0-.07.04-.12.1-.15l.15-.23c-.1.15-.15.32-.15.49.02.17.02.3.02.39-.01.13-.01.23,0,.3l-.06.04v-.06ZM72.42,45.11s.03-.02.02-.04h-.1s-.01,0-.03,0c0,0,0,.01,0,.03.03.02.06.02.1.01ZM72.51,44.76s-.01,0-.03,0c0,0,0-.01,0-.03l-.1.28.07.02.07-.28ZM76.96,47.63l-.04-.02c-.02.09-.03.15-.03.17l.07-.15ZM76.74,47.35h-.03s-.12.2-.12.2c0,.02,0,.03,0,.03.02,0,.03,0,.03,0l.12-.22ZM76.59,48.03l.08.05v-.06c.02-.05.04-.08.04-.08l.08-.21.11-.42c.09-.28.14-.45.15-.49l-.56,1.33s0,.03,0,.03c.02,0,.03,0,.03,0l.07-.15ZM77.24,47.73s-.02-.03-.04-.02l-.07.15h.03s.07-.12.07-.12ZM72.6,44.61s0-.02-.01-.06l-.06.04s0,.06-.04.11c.02,0,.03,0,.04.02l.07-.11ZM72.04,44.14h.03s-.07-.02-.07-.02l-.22.18.04.02.22-.18ZM77.88,48.11c.03-.07.04-.13.03-.17,0-.04,0-.08.01-.1v-.03s-.04,0-.04,0c.01.06.01.12,0,.16-.02.03-.03.06-.04.11.02,0,.03,0,.04.02ZM78.31,48.28s.03-.05.05-.08c.02-.03.02-.05.02-.07l.04-.14s-.01,0-.03,0c0,0,0-.01,0-.03l-.1.28s.03,0,.04.02ZM77.71,48.97c.12-.16.19-.25.2-.27l.07-.15h.03c.02-.12.08-.3.18-.54.02-.03.02-.06.01-.1l.05-.24s0-.02,0,0c.02,0,.03-.02.02-.04l.09-.05s-.01-.05-.02-.09c0-.07.02-.14.05-.21l.06-.31.07.02s.05-.03.08-.08c-.07-.03-.11-.04-.11-.04,0,0,0-.01,0-.03.02-.03.02-.05.02-.07h-.06s0,.21,0,.21l-.09.05s-.02.06-.01.1c0,.02,0,.04-.02.07-.01.13-.04.24-.06.31-.18.37-.31.69-.38.97l-.19.47v.03ZM72.86,44.43s0-.03,0-.03c.02,0,.03,0,.03,0l.08-.21v-.03c-.07.1-.11.18-.12.22,0,0,0,.02.01.06ZM77.15,47.59s-.03,0-.03,0c0-.02,0-.03,0-.03h.03s.09-.35.09-.35l.14-.39v-.06s0-.07,0-.13l.05-.21c-.03.05-.08.15-.13.29,0,.02-.01.04-.06.04l-.07-.02c.06-.01.09-.03.09-.05.02-.03.02-.06.01-.1l-.08.08-.02.07-.13.59.04.06h.03s0,.07-.01.09l-.07.15.04.02.09-.05ZM78.38,47.97c.13-.12.17-.23.12-.35-.03.07-.05.13-.06.18-.01.05-.03.11-.06.18ZM72.41,43.87c-.05-.03-.08-.05-.08-.05l-.05.08s0,.01,0,.03c0,0,.01,0,.03,0l.09-.05ZM78.26,47.15l-.06.18s.03,0,.04.02l.02-.2ZM72.62,43.46c-.06.01-.11.04-.15.07l.04.02.11-.09ZM72.82,43.35v-.03s-.14.13-.14.13l.14-.1ZM78.38,46.76l-.04-.02-.06.18h.06s.04-.15.04-.15ZM72.65,43.75c.05.03.08.04.1.01.02-.03.03-.05.05-.08.04,0,.07-.03.09-.05.02-.03.02-.04.02-.04.05.03.08.04.1.01.01-.05.03-.08.04-.11l.07-.15.07.02s0-.03,0-.03c.02,0,.03,0,.03,0,.12-.07.17-.1.17-.1.06-.03.1-.06.11-.09.03-.05.06-.09.07-.11l.07-.11v-.03s-.04,0-.04,0c-.06.03-.11.08-.17.13-.03.05-.08.09-.14.13-.06.01-.11.05-.14.1-.02,0-.04,0-.06.01,0-.02-.01-.02-.03,0l-.11.09-.06.04-.21.11s-.05.02-.09.05c-.04.03-.03.06.02.09l-.21.11v.03s.09-.02.13-.03c.04-.03.07-.04.09-.02ZM78.6,46.74l.02-.07h-.13s0,0,0,.03c0,0-.01,0-.03,0l.04.02c.05.03.09.05.11.04v-.03ZM77.19,46.27c.05-.06.11-.15.16-.3.04-.14.05-.23.04-.27,0-.07-.03-.14-.11-.21l-.09.51-.06.31.06-.04ZM77.11,45.92c.03-.05.05-.08.05-.08l-.06-.12s.07,0,.06-.01c.02-.03.03-.05.05-.08-.02,0-.03,0-.03,0,0-.02,0-.03,0-.03-.03.05-.06.08-.08.08v.03s-.01.07,0,.13v.06ZM77.8,46.2l.05-.08.09.11-.02.04-.11-.07ZM77.58,45.66c.03-.05.06-.14.07-.28-.06.03-.11.11-.15.23l.04.06h.03ZM78.6,46.58c.05-.06.03-.09-.06-.12h.06s.06-.02.07,0v-.13s-.04-.06-.04-.06c0-.02.01-.04.06-.04.02,0,.03-.02.02-.04.02-.03.02-.07,0-.13,0-.04-.03-.07-.05-.09.12-.03.13-.12,0-.26v.26s-.07.31-.07.31h.03c-.02.09-.05.15-.09.18.03.02.04.06.06.12ZM78.5,45.65h-.03s-.12.49-.12.49l.07.02.09-.51ZM76.68,44.54c-.06-.07-.07-.13-.03-.16.03-.05.06-.09.07-.11l-.04.27ZM78.49,45.62c.01-.13.03-.26.05-.37-.07.06-.11.1-.1.12l.03.13s0,.08-.01.1c.02,0,.03,0,.04.02ZM78.82,45.62l.02-.2v-.33s-.04,0-.04,0l-.1.61.04.02.07-.11ZM78.28,44.98s-.03,0-.04-.02l-.07.15s.03,0,.04.02l.07-.15ZM78.08,45.09s0,.01,0,.03c0,0,.01,0,.03,0l.02-.07-.14-.04.06-.04h.03s.06-.02.06-.02c-.04,0-.07,0-.08-.05,0-.04,0-.11.02-.2l-.09-.11s-.04.02-.06.04c-.02.03-.02.05-.02.07v.3s.07.18.07.18l.08-.08ZM74.55,42.55c.06-.01.12-.05.17-.1.05-.06.08-.12.09-.18-.06.03-.12.08-.2.14-.05.06-.11.1-.17.13h.1ZM73.44,41.52v-.03s-.04-.02-.04-.02l-.13.16v.03s.17-.13.17-.13ZM78.11,44.49s0-.03.02-.04l-.14-.04-.04-.02.04-.14s0-.02-.01-.06l-.05.08v.16s0,.08,0,.1l.15-.07.04.02ZM73.67,41.37l-.14-.04s-.05.03-.08.08c.05.03.08.05.08.05l.14-.1ZM78.45,45.01l.04.02v.06s.04,0,.04,0c-.01-.06,0-.14.01-.23h-.03s0,.02-.02.04c0,.02,0,.04.01.06,0-.02-.02-.03-.04-.02-.02-.17-.03-.38-.04-.61.01-.24,0-.45-.07-.61l.03,1.5.04.02v-.23ZM77.98,44.19s0-.04-.01-.06c.02-.03.02-.04.02-.04-.03-.02-.06-.02-.1-.01l.09.11ZM78.83,44.8l-.02-.09c-.02-.1-.03-.19-.02-.26h-.03s.04.36.04.36l.04.02v-.03ZM78.69,44.73c0-.18,0-.31-.02-.39h-.03s-.01.4-.01.4l.04.02.02-.04ZM75.02,41.89l-.09.02-.02.04c.06-.01.1-.01.1.01l.02-.07ZM77.03,43.29l-.05-.22h-.03s-.03.01-.03.01v.06c.03.06.05.1.07.12v.06s.04-.04.04-.04ZM78.79,44.15l-.02-.09h-.03s-.01.11-.01.11l.04.06.02-.07ZM73.69,41.33c.07-.06.13-.12.16-.17.04-.03.07-.06.11-.09.04-.03.09-.05.15-.07.02,0,.05-.01.09-.02.04-.03.05-.07.04-.11l.07-.15s.03-.02.02-.04c.02,0,.03,0,.03,0,0-.02,0-.03,0-.03h-.03s-.08.07-.14.1c-.04,0-.07.05-.07.11,0,.07-.08.14-.22.21l-.32.2c.05.03.09.05.11.04ZM77.89,43.49c-.01-.06,0-.1.01-.1v-.06s-.03-.03-.05-.02l-.04.11s.03.05.08.08ZM78.76,44.02s.03-.02.02-.04l-.02-.26s-.06.06-.07.15c0,.07,0,.12.03.16h.03ZM75.39,41.78s0-.11,0-.19h-.03s-.02.21-.02.21h.06ZM75.09,41.61s.02,0,.06-.01l.09-.05s.05-.04.09-.05v-.06s-.25.12-.25.12v.03s-.02.04-.02.04c.02,0,.03,0,.03,0ZM78.34,44.18c-.01-.26-.02-.48-.01-.65l.03.16h.03s-.02-.4-.02-.4c-.04,0-.07.03-.09.05v-.03c.07-.04.08-.11.01-.2,0-.02-.02-.04-.04-.06-.03-.02-.05-.03-.08-.05-.02-.08-.04-.14-.07-.18l.2,1.36h.03ZM74.95,41.55s.08-.08.19-.17c.02-.03.06-.03.13-.03.08-.02.14-.05.17-.1.13-.03.15-.08.07-.15-.02,0-.05.01-.09.02-.03-.02-.05-.01-.06.01-.29.15-.48.25-.56.29h-.03s0,.04,0,.04c.03.02.05.02.07.02.04,0,.06,0,.07.02v-.03s-.03.06-.02.1h.06ZM77.82,43.28c.03-.05.05-.08.05-.08.01-.05,0-.09-.03-.13,0-.04,0-.09,0-.13,0-.04-.03-.09-.07-.15-.04-.08-.04-.14,0-.19l-.12-.1h-.03c-.09.09-.09.17.02.23l.1.17-.02.07.05.25.04.06ZM74.71,40.62v-.06s-.31.16-.31.16l.04.06.26-.16ZM76.22,41.66c.14-.05.28-.14.4-.25h-.13s.02-.07.02-.07h-.13s-.01-.01-.04-.03c0-.02-.02-.03-.04-.02-.02,0-.07.02-.16.03-.08.02-.14.05-.17.1-.02-.08-.07-.12-.15-.1-.06.01-.12.01-.16,0l.12-.06c-.07-.03-.15-.02-.23.02-.08.02-.14.05-.17.1,0,.04.02.06.04.06l.13-.03s.07.02.13,0v.16s-.13-.17-.13-.17l-.05.21s0,.06-.04.11v.03s.06-.04.06-.04c.08.05.13.06.17.03.19-.04.32-.08.4-.12h.13s0,.04,0,.04ZM75.98,41.19l-.09.02.11.07-.02-.09ZM78.55,43.02s.03-.02.02-.04l-.07-.18h-.03s.08.22.08.22ZM74.81,40.6c.06-.01.11-.05.14-.1v-.03s-.14.13-.14.13ZM74.85,40.36l-.07-.02-.03.17.04.02.06-.18ZM77.97,42.33l-.11-.21s0,.03-.02.04l.07.18h.06ZM82.96,55.29c-.05-.03-.14-.06-.28-.07-.01.05-.04.05-.09.02-.16,0-.25-.05-.29-.13l-.13-.17-.09-.11v-.06s-.04-.07-.07-.09h-.03s-.04-.06-.1-.14c0-.02-.02-.05-.05-.09,0-.02,0-.06,0-.13.02-.03,0-.09-.07-.18-.03-.04-.06-.03-.09.02v.03s-.03,0-.03-.02c-.03-.13-.06-.22-.09-.27,0-.02-.03-.05-.08-.08v-.06s.02.02.02.02h.03c-.01-.07-.03-.1-.05-.09-.02,0-.03,0-.04-.02-.01-.06-.01-.11,0-.13,0-.02-.01-.05-.02-.09v-.03s-.03.04-.03.04v.06s-.02,0-.02,0c-.03-.02-.04-.06-.06-.12-.03-.04-.04-.07-.02-.09,0-.02,0-.04-.01-.06h.03c.03-.06.05-.09.04-.11,0-.02-.03-.05-.08-.08-.03-.04-.05-.1-.07-.18-.02-.08-.02-.18,0-.29,0-.11,0-.18-.02-.23.01-.05.02-.1.03-.17,0-.07.02-.14.05-.21.01-.13.02-.21.01-.23v-.03s-.02,0-.04,0c0,0,0,.01,0,.03l-.05.24c-.02.09-.03.16-.02.2l-.06.04v-.06s-.02-.11,0-.2c-.01-.06,0-.14.01-.23,0-.09,0-.17.01-.23,0-.07.01-.13.02-.2l.03-.3s.02,0,0,0c0-.02,0-.03,0-.03v-.06s-.02-.11,0-.2v-.03s-.04,0-.04,0l-.02.07-.02.04v-.03s-.02,0-.04,0c0,0,0-.01,0-.03v.03s-.05.21-.05.21l-.02.04v-.03c-.02-.08-.03-.15-.02-.19-.01-.06-.01-.11,0-.13.01-.05.02-.09.04-.14l-.04-.19h-.03s-.03.02-.02.04l-.06.04s-.01,0-.03,0c0-.02,0-.03.02-.04-.02-.08,0-.14.03-.17v-.03c0-.09,0-.19.03-.3.02-.11.03-.19.05-.24.02-.09.03-.16.02-.2.02-.03.01-.04,0-.03,0-.02,0-.04-.01-.06-.04,0-.06.02-.06.04,0,0-.02.03-.05.08l-.02-.09.04-.14v-.03s-.04,0-.04,0c0,.04,0,.09-.04.14v.03s-.01-.03-.03-.02v-.13s0-.03,0-.03c-.02,0-.03.02-.02.04-.03.05-.04.11-.03.17-.02,0-.03.02-.02.04h.06s0,0,0,.02c0,0,.01,0,.03,0-.02,0-.03.02-.02.04-.07,0-.09.03-.07.11l-.16.46v-.03s.03-.27.03-.27c.04-.21.07-.41.1-.61l.09-.48.02-.07s-.06.02-.06.04l-.05.21-.02.07s0-.06.02-.07l.14-.72c.06-.21.13-.54.21-1l.12-.52c.03-.16.07-.33.12-.52.04-.21.07-.42.09-.64,0-.13,0-.24.03-.33.02-.09.04-.17.05-.24.06-.32.1-.56.11-.71l.11-.84.1-.61c.03-.27.04-.47.03-.6l.06-.18c.06-.34.09-.63.1-.87,0-.09.03-.22.07-.41l.03-1.09.12-.52.03-.3.05-.21.05-.08c-.01-.06-.01-.16,0-.3l.13-.32s.02-.06.01-.1c.03-.05.06-.08.08-.08.06-.01.13-.05.21-.11v-.03c0-.07,0-.15-.03-.26-.01-.06.03-.13.12-.19.04,0,.07-.03.09-.05.02-.03.03-.05.05-.08,0-.02,0-.06.04-.11,0-.02,0-.03.02-.04l-.02-.09.06-.04-.02.04.04.06s.03,0,.03,0c0-.02,0-.03,0-.03.04,0,.06,0,.07.02h.03s.03-.01.03-.01v.03s-.05.18-.05.18l.02.09.02-.07s.04-.06.14-.13c.02,0,.06-.01.13-.03.08-.04.13-.09.16-.17l.02-.04.04.06s.03.07.05.09c.03-.05.05-.08.05-.08.02-.03.07-.15.15-.36.07-.06.12-.11.13-.16,0,0,.01,0,.03,0,.02,0,.03,0,.04.02.03.06.09.06.16,0,0-.02,0-.03.02-.04l-.02.07s0,.04-.02.07c-.02.03-.01.05.01.06.03.02.07.02.13,0,.08-.02.11-.07.07-.15,0-.04,0-.07.05-.08.06-.01.11-.05.14-.1.04-.03.09-.05.15-.07.06-.01.12-.01.16,0l.08.05s.03.09,0,.16c-.01.05-.02.08-.01.1,0,.04.02.06.04.06v.03s-.1.12-.1.12v.06c.14.06.22.21.27.43l.05.25c.04.17.04.41.02.72.01.15.05.37.11.66l.04.19c.05.25.14.51.27.79.07.14.17.37.28.69.04.08.06.16.05.25.02.08.05.16.09.24.02.1.08.26.16.46.08.29.22.64.39,1.06l.31.82.24.64c.11.28.18.51.21.67.11.32.19.57.23.74,0,.02.02.03.04.02.03.13.08.29.17.49l.1.14c.06.05.13.21.23.47,0,.04.02.1.04.19.03.06.04.12,0,.19l.04.06.06-.04.07-.41.12-.52.11-.38.07-.28.14-.39.09-.35.04-.27s.04-.17.08-.38l.15-.69c0-.07.02-.12.03-.17,0-.07.02-.12.03-.17l.06-.31.16-.79.04-.4.15-.69.13-.62.13-.75.22-.93c.02-.11.04-.22.06-.31.04-.1.07-.18.08-.25.05-.16.11-.41.17-.72l.15-.69.07-.11v.1s-.08.44-.08.44l-.02.07c-.05.06-.08.17-.09.35,0,.02,0,.08-.03.17,0,.09-.03.22-.07.41-.02.09-.05.16-.08.21,0,0,0,.01,0,.03,0,0,.01,0,.03,0h.03s.01-.24.01-.24l.03.12.02.09s-.02.05-.02.07c.03.02.06,0,.09-.02.04-.03.06-.01.08.05-.03-.02-.05-.01-.06.01-.02.03-.02.04-.02.04v.06s.05.02.05.02c.05-.08.06-.12.04-.14.07-.06.09-.13.05-.21,0,0-.01,0-.04-.02,0-.04,0-.07.05-.08-.01-.06,0-.1.04-.11.02,0,.03-.03.02-.07-.05-.03-.04-.06.02-.07v-.03s-.04-.02-.04-.02c.02-.03.02-.05.02-.07l.05-.37.05-.21s.04-.11.08-.25l.02-.07h.1s.03,0,.03,0c.02-.03.01-.05-.01-.06h-.03s-.09.06-.09.06l.03-.17.06-.04h.03s.06.02.09-.03l.06-.18s0-.06.02-.07l.02-.07v.06s-.04.37-.04.37l-.02.07c-.03.05-.04.08-.01.1-.02.03-.02.06-.01.1.03.02.03.04.01.06v.03s0,0-.02,0c0,0,0-.01,0-.03v-.03s-.01-.03-.01-.03v.03s-.03.14-.03.14c-.03.05-.02.08.05.09v.06c0,.09-.01.17,0,.23,0,0,0,.02-.02.07,0,.02.03.03.07.02l.02.09s-.03.02-.02.04h.06s.06-.19.06-.19c.04-.1.09-.26.12-.49l.04-.27s0-.03,0-.03c.02,0,.03,0,.03,0v.03c-.04.16-.07.32-.05.47v.03s.04-.02.03-.04l.06-.34s.04-.15.1-.32c0-.02,0-.03,0-.03.02-.03.01-.05-.01-.06,0-.02,0-.03.02-.04.02-.03.02-.06.01-.1l.04.02s-.02.05-.02.07c.03.02.03.04.01.06-.02.03-.01.1.02.23l.06-.04.05-.24c.03-.05.07-.08.11-.09l.06-.04.02-.07-.02.04-.06.04s0-.06.02-.07c0-.02,0-.06.04-.11h.03s.03-.18.03-.18c.02,0,.03,0,.03,0,0-.02,0-.03,0-.03.08-.02.11-.09.08-.21,0-.02,0-.03.02-.04.04-.03.07-.04.09-.02.09.02.16.02.19,0h.06s0,.02-.02.02l-.19.34-.08.38s-.03.02-.02.04c.02,0,.03-.02.02-.04.04-.03.07-.09.09-.18l.06-.18c0-.09.06-.18.17-.27.04-.03.07-.09.09-.18l.07-.11h.06s.02.08.02.08l-.02.04h.03s.06-.04.05-.08c-.03-.02-.03-.03,0-.03.02-.03.03-.04.06-.04.06-.01.1-.08.12-.19,0,0,.07-.1.2-.3v.03s-.07.25-.07.25c0,.07,0,.13.04.19.05.03.09.05.11.04.06-.01.08,0,.04.06l-.04.11c-.13.2-.22.44-.27.71-.09.39-.14.77-.14,1.14-.02.11-.04.24-.05.37,0,.13,0,.25-.02.36-.02.29-.07.62-.15.98,0,.15-.05.39-.11.71,0,.07-.02.19-.05.37,0,.16-.04.3-.1.45v.16s-.11.84-.11.84l-.06.63c-.04.34-.07.55-.09.64,0,.13-.02.28-.07.44-.03.25-.1.51-.19.79,0,.22,0,.37-.03.47l-.02.07-.06.34-.06.8-.06.63c0,.07-.02.12-.03.17-.02.03-.03.05-.05.08,0,.04,0,.08-.01.1,0,.02,0,.08-.03.17-.07.37-.14.62-.19.76l-.05.21s0,.06-.02.07l-.17.72c-.1.24-.14.48-.11.71l-.06.31-.07.57c-.04.12-.07.24-.08.38,0,.11,0,.21-.03.3-.03.07-.02.19.01.36.02.08.07.13.16.13.07,0,.11.03.11.07.03.04.04.08.03.13l-.03.3.02.26c.02.08,0,.14-.06.18l-.22.18-.06.04c-.02.09-.09.16-.18.2-.08.04-.13.06-.15.07l-.2.14s-.1.03-.18.07c-.07.06-.15.09-.21.08l-.55.05-.21-.05c-.36-.05-.62-.1-.79-.16-.07,0-.13-.03-.18-.06-.03-.04-.07-.06-.11-.07-.18-.13-.38-.33-.59-.59-.17-.2-.37-.5-.59-.89l-.41-.66-.21-.51c-.07-.12-.11-.23-.14-.33-.08-.16-.18-.42-.3-.79-.05-.12-.11-.29-.18-.52-.07-.22-.13-.43-.17-.62-.04-.1-.07-.19-.09-.27,0-.11-.02-.21-.07-.31l-.1-.47c-.09-.2-.14-.35-.16-.46l-.24-.8c-.04-.17-.11-.39-.21-.67-.03-.15-.1-.36-.21-.64-.01-.06-.05-.11-.1-.14l-.04.14c-.05.18-.07.32-.07.41.02.08.02.18,0,.3-.02.09-.04.16-.05.21l-.07.41c-.04.14-.07.28-.11.42-.04.14-.06.26-.08.38-.07.39-.12.61-.15.69,0,.07-.04.17-.1.32.01.06.01.11,0,.13,0,.04-.02.17-.08.38,0,.04-.02.17-.08.38l-.2.89-.19.76-.14.85-.08.54c-.04.21-.07.33-.08.38l-.04.27c-.03.07-.05.17-.06.31,0,.09,0,.19,0,.3,0,.09-.02.18-.04.27-.03.38,0,.71.05,1l.1.47.09.41c.06.18.21.4.44.66,0,.02.02.03.04.02.03.02.04.03.04.06.03.02.04.05.05.09-.04,0-.06,0-.07-.02-.03-.02-.05,0-.09.05-.03.07-.08.08-.16.03l-.18-.09ZM81.43,54.42s-.03,0-.04-.02l-.06-.28.04.06.05.22s.04.02.04.02c-.02,0-.03,0-.03,0ZM81.55,54.39s-.03,0-.04-.02l-.08-.08v-.1s.04,0,.04,0c.03.04.05.1.07.18v.03ZM81.42,54.09s-.06-.03-.09.02v-.13s0-.03.03-.04c0,.02,0,.03,0,.03l.09.11s0,.03-.02.04v-.03ZM80.91,53.38v-.23s0-.03,0-.03v.03c.03.1.03.18.02.23h-.03ZM81.53,53.7s.03-.02.02-.04c.02-.03.02-.07,0-.13v-.03s-.04.02-.03.04c-.02.03-.02.07,0,.13v.03ZM81.39,51.38l-.08-.05-.03.17h.03s.07-.12.07-.12ZM80.38,50.19c.04-.14.06-.22.08-.25v-.03s0,.03,0,.03l-.04.27s-.03.02-.02.04v-.06ZM81.3,50.51c.06-.12.07-.28.03-.47h-.03c-.01.05-.02.1-.04.15-.02.03-.02.07,0,.13.02.08.02.15,0,.19v.03s.03-.04.03-.04ZM82.18,49.17s.03-.02.02-.04l.04-.14v-.03s-.04,0-.04,0c0,.02,0,.08-.03.17v.03ZM82.65,47.27h-.03s-.06.18-.06.18v.03s.04,0,.04,0l.05-.21ZM81.75,46.71c.02-.09.03-.15.03-.17v-.03s-.06.21-.06.21h.03ZM82.68,47.1s.03-.02.02-.04l.02-.04c.06-.32.12-.56.17-.72,0-.02,0-.06,0-.13,0-.07.02-.11.04-.14l.08-.54.09-.35v-.03s-.04.02-.03.04l-.08.25.02.09s-.02.03-.05.08c-.11.5-.18.88-.21,1.13l-.08.38v.03ZM86.73,48.25l-.05-.09-.02.07.05.09.02-.07ZM86.66,47.15l-.08-.08s-.02-.03-.04-.02v.03s.07.12.07.12c.02,0,.03,0,.04.02l.02-.07ZM83.18,44.73l.02-.2v-.03s-.06.21-.06.21v.03s.04,0,.04,0ZM86.48,46.93l.02-.07v-.03s-.02,0-.04,0c0,0,0,.01,0,.03l-.02.04c.05.03.08.05.08.05l-.04-.02ZM86.67,45.84l-.02-.09h-.03s-.03.01-.03.01v.13s.03,0,.03,0l.06-.04ZM85.99,45.27l-.03-.13-.04-.02v.03s-.01.06,0,.1v.03s.04,0,.04,0h.03ZM85.3,44.21l-.02-.09v-.03s-.04,0-.04,0c.01.06.01.11,0,.13,0,.02.03.03.07.02v-.03ZM85.95,43.9l.02-.04v-.03s-.07.01-.07.01c0,0-.01,0-.03,0,0,0,0,.01,0,.03.03.02.04.05.05.09l.02-.07ZM85.79,43.48s0-.03,0-.03c.02,0,.03,0,.03,0l.02-.07s-.04-.01-.04-.06h-.03s.04.06.04.06c0,.02,0,.03-.02.04v.06ZM90.26,44.44l-.07.11.04.02.04-.14ZM84.18,39.96s0-.03,0-.03c.02,0,.03,0,.03,0l-.05-.09-.02.07.04.06ZM90.09,43.98c0-.07.04-.12.1-.15l-.04-.02h-.03s-.07.12-.07.12c0,0,0,.01,0,.03,0,0-.01,0-.03,0l.07.02ZM90.27,43.91c.08-.02.11-.07.07-.15v-.03s-.05-.06-.05-.06l-.02.07s.02.05-.01.1l-.02.07h.03ZM90.24,43.29l-.04-.02-.07.11.08.05.04-.14ZM90.23,42.8s.03-.02.02-.04c.08-.02.12-.06.1-.12,0-.02-.02-.03-.04-.02l-.02.04s0,.06-.06.04l-.02.07v.03ZM90.61,42.16l.02-.07v-.06s-.08-.02-.08-.02v.03s.04.04.02.06l-.02.07h.06ZM90.47,41.8l.04-.27h-.06s0,.04,0,.04c.02,0,.04.01.04.06-.03.05-.05.09-.04.11l.02.09v-.03ZM90.65,41.73s.03-.02.02-.04l.04-.14v-.03s-.04,0-.04,0l-.07.15.04.06ZM90.66,41.47s.05-.03.08-.08c0,0-.01,0-.03,0t0,0s-.06.03-.05.08ZM90.79,41.31v-.06s-.07.04-.07.04h-.03s0,.04-.02.04l.07.02.06-.04ZM90.73,41.06v.03s.07-.02.06-.04c0-.02-.03-.05-.08-.08l-.04.14.06-.04ZM90.78,40.98s0-.03,0-.03c.02,0,.03,0,.03,0v-.03s-.01-.02-.02-.06h-.06s.04.07.04.07v.06ZM90.65,40.81v-.13s0-.03,0-.03h-.03s0,.14,0,.14v.03s.04,0,.04,0ZM90.84,40.77s0-.04-.01-.06c.01-.05.03-.09.07-.15l-.08-.08h-.03s.02.1.02.1v.03s-.01.06,0,.1c0,.02,0,.04-.02.07v.03s.06-.04.06-.04ZM90.89,40.4s-.03-.04-.01-.06c.04-.03.05-.06.05-.08v-.06s-.07.04-.07.04v.1s-.06.08-.06.08l.09-.02ZM90.97,39.89s0-.03.02-.04h-.06s-.01.02-.03.02c0,0,0,.01,0,.03l.04.06.02-.07ZM90.98,39.5c.03-.05.04-.1.04-.14l-.07.11s.02.03.04.02ZM91.1,39.44s.06-.02.06-.04c0-.02-.02-.03-.04-.02l-.06.04s0,.03,0,.03c.02,0,.03,0,.03,0ZM91.24,38.85s0-.08.01-.1h-.03s-.01.11-.01.11v.03s.03-.04.03-.04ZM91.28,37.86s.02-.03.05-.08l.05-.37v-.06s-.02-.03-.02-.03c-.02.03-.05.04-.09.05l-.02.04c.05.03.08.05.08.05,0,.02,0,.03-.02.04-.02,0-.03.02-.02.04.02.1.02.18-.01.23l.02.09ZM91.04,36.9c.05-.08.07-.11.07-.11l-.07-.02s0,.06-.04.11l.04.02ZM91.11,36.62s-.02-.03-.04-.02l-.02.07.04.06v-.1ZM91.17,36.44l-.07-.02-.02.04s0,.01,0,.03c0,0,.01,0,.03,0l.06-.04ZM91.85,35.67l.07-.11v.13s-.03.04-.03.04l-.04-.06ZM92.47,35.93s0-.06.04-.11l-.04-.02s-.06.03-.05.08l.04.06ZM91.93,35.56c-.01-.06-.04-.08-.08-.05,0-.02,0-.06.04-.11h.03s.01-.04.06-.05c0,.04,0,.08-.01.1,0,.02,0,.06-.04.11ZM91.94,35l.04-.14.04.02-.07.15v-.03ZM106.94,42.97s-.04-.05-.05-.09l-.04-.06-.06-.12v-.03s-.03.04-.03.04l-.04.14s-.03.04-.06.04c0-.02,0-.03,0-.03-.03-.04-.06-.04-.1-.01-.04,0-.06.01-.06.01-.02.03-.04.04-.06.04-.03-.02-.05-.02-.07-.02-.18,0-.29,0-.33,0-.11,0-.19-.03-.25-.11-.16-.14-.27-.25-.33-.32-.14-.14-.23-.29-.26-.44v-.13s-.04-.19-.04-.19l-.03-.29-.03-.13c-.03.05-.04.1-.04.14,0,.04,0,.08-.01.1l-.05.08-.05-.09c-.02-.08-.02-.19,0-.33l-.05-.22c.03-.07,0-.1-.08-.08-.08.02-.14-.04-.17-.16l-.09-.41v-.03s-.03.04-.03.04c0,0-.02.03-.05.08l.02-.07.03-.3.06-.18c.04-.1.09-.24.14-.42.11-.29.19-.5.22-.64l.05-.24v-.03s-.07.01-.07.01c0,0-.04.06-.12.19h-.03s0-.02,0-.02v-.06s-.1.05-.1.05l-.06.04v-.06s-.06-.06-.06-.06l-.06.04c-.05.08-.07.11-.07.11h-.03s-.01-.06-.01-.06c.06-.03.09-.09.1-.15,0-.07.02-.12.03-.17,0,0,.02-.03.05-.08.03-.05.05-.08.05-.08.02-.03.04-.03.06-.01.02.02.05.01.06-.01.07-.06.21-.09.41-.09.1-.02.18-.07.23-.15.07-.1.09-.19.07-.28-.01-.06.01-.14.08-.25.12-.16.19-.26.23-.31.13-.22.26-.41.4-.55.24-.2.44-.41.62-.63l.4-.58s.06-.09.17-.27l.38-.67.49-.89.44-.98.14-.55s.02-.08,0-.16l-.05-.09c-.02-.08,0-.18.07-.28.06-.12.1-.23.13-.32.04-.12.07-.21.1-.28v-.03s-.04,0-.04,0l-.2.14-.7.55-.3.29-.3.26c-.12.14-.19.21-.22.21l-.38.38-.63.56c-.1.06-.2.15-.3.26-.11.09-.24.19-.39.31-.12.14-.19.24-.19.3l-.06.04-.35.18h-.03c-.07,0-.15,0-.26.03-.04,0-.13,0-.26,0-.03-.02-.06-.02-.1-.01-.08.02-.17,0-.27-.04-.1-.04-.16-.07-.18-.09-.12-.04-.22-.11-.31-.2-.07-.03-.14-.08-.2-.15-.04-.1-.08-.17-.11-.21-.05-.03-.08-.06-.08-.08-.2-.2-.43-.34-.69-.44h-.1c-.09-.03-.17-.08-.23-.16l-.15-.23s-.02-.09.03-.17l.25-.35.35-.34.1-.12c.08-.13.21-.23.39-.31l.79-.43c.06-.03.21-.16.44-.39l.33-.27.2-.14.78-.63c.28-.21.53-.39.74-.52.23-.14.42-.25.55-.35.19-.13.33-.21.43-.26l.31-.23.15-.07c.12-.05.22-.1.29-.16.1-.06.17-.11.23-.15.07-.06.23-.14.47-.23.06-.03.15-.07.28-.09l.24-.09c.06-.01.18-.02.36-.01.02,0,.05,0,.1.01.07,0,.12.03.15.07l.18.09s.02.04.04.06c.02,0,.03,0,.03,0,.04-.03.08-.04.12-.03.04,0,.08-.03.12-.06h.03s-.03,0-.03,0c0-.02,0-.03,0-.03l-.06-.12s.07.02.13,0c.09.02.17.05.22.08.14.04.22.06.25.08.07.03.13.07.19.12l.18.09c.19.09.34.17.44.23.02,0,.03,0,.04.02.04.1.12.18.22.25.13.08.19.12.19.12.09.02.11.05.05.09,0,.02,0,.04-.02.07,0,0,.01,0,.04.02l.28.4s.02,0,0,.03c0,0,.01,0,.04.02.01.06.03.1.06.12.09.02.2.11.32.26,0,.04,0,.08-.01.1-.04.03-.05.09-.03.17.01.06.03.1.06.12.05.01.05.04.02.09l-.02.07h.06s.07,0,.07,0l.03.16c-.07.06-.13.15-.17.27-.04.12-.07.21-.1.28l-.66,1.62s-.14.26-.42.78c-.18.39-.32.68-.43.88l-.35.63-.48.96-.43.75-.7,1.14c-.11.18-.34.48-.69.9l-.23.31s-.02.04-.07.11l-.11.22c-.06.14-.14.32-.24.54-.09.19-.19.42-.31.69l-.3,1.02c-.08.32-.11.59-.09.8,0,.04-.01.09-.07.15-.02,0-.04.02-.06.04-.02.03-.02.05-.02.07-.05.18-.15.37-.3.56-.04,0-.06.02-.06.04ZM106.29,48.09c-.05.08-.16.1-.34.07l-.14-.07c-.05-.03-.1-.03-.13,0-.04.03-.11,0-.21-.08-.04-.08-.12-.1-.25-.08-.06.01-.13-.01-.21-.08l-.34-.22c-.12-.06-.25-.19-.38-.38v-.06s-.02-.08-.07-.09c-.03-.04-.06-.04-.1-.01-.02.03-.06.03-.12.03h-.03s-.16.04-.16.04c-.08.02-.14.06-.17.13,0,.02,0,.03-.02.04v-.03s-.02-.06-.02-.06c0,0-.01,0-.03,0,0,0,0,.01,0,.03l-.07.11s-.07.03-.09.05v-.06s0-.07,0-.07c.03-.05.03-.11,0-.16-.01-.06-.02-.1-.03-.13-.02,0-.04-.01-.04-.06.06-.21.09-.34.08-.38.1-.35.18-.57.25-.68.07-.1.12-.17.15-.2.1-.15.29-.37.58-.65l.19-.17.28-.22s.09-.05.15-.07c.08-.02.12.02.12.1,0,.04.03.07.05.09s.06,0,.09-.02c.02-.03.04-.04.09-.05.04-.03.1-.05.18-.07.12-.03.24-.02.33.03.16.03.26.11.31.23.05.03.06.06.02.09,0,0,0,.02.01.06,0,.02.02.04.04.06l.37.18.08.05c.1.17.15.34.14.49-.02.03-.02.06-.01.1l.07.31c.01.06.03.1.06.12.1.04.14.13.12.27,0,.07-.06.13-.15.2-.06.03-.08.08-.07.15,0,.02,0,.08,0,.16,0,.07-.03.13-.06.18v.06s.04.04.03.06c-.13.09-.2.2-.2.3,0,.09-.04.15-.12.19l-.23.15ZM105.74,44.96s.02,0,.06-.01l.09-.02v.03s.12-.09.12-.09l-.11-.07s-.03-.03-.07-.02c-.02.03-.04.03-.06.01-.03-.02-.05-.02-.07-.02l-.41.06s-.04.02-.06.04c0,.02,0,.03,0,.03v.06c.15.01.24.02.28,0,.03.02.06.02.1.01.06-.03.1-.04.13-.03ZM103.98,41.22v-.03s-.05-.06-.05-.06h.06s.04-.03.06-.06c.04-.03.05-.07.04-.11-.03-.13-.04-.24-.04-.35l-.07-.18v-.03s.03,0,.03.02c.06.05.1.15.13.3v.3c-.03.05-.05.09-.04.11l-.02.07h.03s-.02.06-.02.06l-.11-.04ZM104.29,41.02l-.03-.13h-.03s.11-.25.11-.25c0-.02,0-.03.02-.04,0,0,0,.01,0,.03,0,0-.01,0-.03,0v.3s-.02.07-.02.07l-.02.07v-.06ZM105.86,41.6s0-.03.03-.04l.08-.25s-.04-.01-.04-.06l-.05.08s-.02.03-.05.08v.06s.02.02.03.06v.06ZM107.66,37.54l.1-.15c.03-.05.05-.09.04-.11-.04,0-.07.03-.09.05l-.15.23-.02.07.11-.09ZM108.11,36.91l.12-.22s.02-.04.07-.11l-.1.12-.12.19s-.03.02-.02.04c.02,0,.02,0,0,.03l.06-.04ZM108.43,36.55s0-.03,0-.03c.02,0,.03,0,.03,0,.06-.1.14-.25.23-.44.02,0,.03,0,.03,0,0-.02,0-.03,0-.03h-.03s-.08.09-.08.09c-.03.05-.06.12-.08.21-.03.07-.06.12-.1.15v.06Z\"><\/path><path class=\"cls-1\" d=\"M162.17,46.89l.07-.16s-.08.03-.07.16Z\"><\/path><path class=\"cls-1\" d=\"M163.61,39.99s.01.04.03.03l-.02-.06v.03Z\"><\/path><path class=\"cls-1\" d=\"M165.39,48.56c0-.28.01-.54.03-.79.02-.24.02-.46.03-.68.04-.42.05-.8.07-1.17.03-.74-.02-1.52-.35-2.66-.21-1.12-.65-2.26-1.06-3.28-.25-.18-.38-.51-.51-.87-.07-.17-.14-.35-.2-.52-.08-.16-.19-.31-.32-.41l.09-.29c-.17-.15-.35-.33-.34-.59l.06-.02c-.28-.21-.35-.57-.48-.67l.06-.02-.21-.32.1.02c-.41-.42-.7-.88-.91-1.36l-.18.16c-.36-1.04-.98-1.09-1.3-2.04l.06-.02c-.63-.28-.84-.72-1.08-1.16-.11-.22-.24-.44-.4-.63-.08-.1-.18-.18-.31-.28-.12-.08-.26-.15-.44-.21.16.06.04-.12.09-.17-.46-.37-.95-.76-1.28-.41-.29-.29-.13-.34-.06-.51-.14.16-.48-.02-.74-.22l.17.04c-.25-.18-.52-.35-.77-.53l-.11.41c-.31-.39.21-.45-.23-.66l-.19.25c-.51-.44-.55-1.07-.99-1.63-1.17-.82-2.56-1.33-3.96-1.76-1.38-.43-2.75-.76-3.95-1.31l-.06-.26c.04-.36-.85.35-.86.03l-.35.1c-.08-.08-.24-.16-.09-.22-.27-.06-.29,0-.52.06l-.26-.26c-.28-.08-.54-.11-.81-.12-.28-.02-.54,0-.81,0-.53.02-1.09.1-1.67.03-.7-.23-1.76-.24-2.79-.08-.25.04-.53.08-.78.14-.25.06-.51.12-.74.17-.49.13-.93.27-1.31.4-1.05.42-2.2.48-3.41.65-1.2.14-2.44.38-3.36,1.12-.09,0-.22.18-.2.19-.31.13-.64.26-.94.42-.3.14-.63.3-.92.46,0,0-.14.06-.37.21-.22.13-.55.31-.89.55-.7.46-1.49,1.1-2.02,1.7-.51.6-.76,1.12-.41,1.33.17.1.5.14,1,.09.26-.04.56-.07.9-.13.33-.07.73-.14,1.19-.22l.03.07c.21-.09.43-.17.61-.27.2-.08.35-.19.52-.29.31-.19.56-.42.78-.77.32.37.76-.35,1.05-.32v.04c.2-.27.53-.36.85-.4.32-.04.63-.11.85-.35,0,.05.02.16-.1.21.39-.22.9-.52,1.02-.26.23-.09.5-.2.76-.29.27-.11.56-.18.82-.27.27-.11.53-.19.76-.31.23-.09.43-.24.55-.37l-.04.08c.31-.36.48-.15.87-.37.01.04.06.04.07.06.18-.18.49-.24.76-.29.3-.04.57-.04.74-.13l.06.17c.26-.04.51-.08.78-.12h-.32c.04-.25.2-.19.43-.11.23.08.5.19.79,0,.28.02.56-.25.86-.5.29-.25.61-.46.9-.34.29-.23-.26.37.16.19,0,.26-.2.17-.11.37.42-.13.65.28,1.17.11v.19c.34-.18.65-.07.91.02.28.08.5.19.76.04.71-.09.34.64,1.08.36l.21.3c.29.1.27-.28.57-.1-.07.18.38.21.13.34.32.19.7.19,1.1.22s.84.09,1.21.46c.15-.13.34-.12.51-.08.17.04.32.07.44-.03-.03.14.9.35.26.45-.06.02-.12-.02-.09-.07l-.14.16c.17.26.41.31.68.31.25,0,.55-.03.77.12-.12-.13-.3-.2-.1-.26l.43.24-.18.12c.21.13.42.26.6.4l.03-.23c.26.26.19.61.69.56.25-.06-.16-.41.21-.28.16.17.38.41.61.64.22.23.45.46.69.67.09-.23.22-.13.4-.07l-.11.17c.71.14-.08.49.55.68l-.14.06s.41-.21.41-.21c.73.03-.05.52.83.51-.21-.13.22-.41.39-.16l-.19.08c.17.1.27.06.32.19-.15.02-.24.18-.03.32l-.29.07.61.06c.13.4.72.64.63.93,0,0,.11.17.26.33.15.15.35.31.53.28-.25,0-.03.38-.28.44.3,0,.84.37.79.71l-.05-.02c.09.22.22.39.34.53.12.14.26.28.41.42.28.25.52.54.64.95.18-.16.29.27.51.03.17.15.28.32.35.5.07.19.1.37.14.53.06.15.11.28.19.38.1.09.25.12.5.08.21.32,0,.52.05.71l-.09-.05c.38.62.47.82.64,1.31.19.2.62.09.68.59-.21-.09-.12.09-.06.26-.06-.1-.13-.12-.16.15.07.01.11.04.15.09,0,0-.02,0-.04.02.15.26.19.2.18.06.02,0,.06-.02.08-.08-.12.37.28.84,0,.97.32.84.77,1.41,1.03,2.15-.13.12-.3-.03-.4-.23l.16.52c-.23.05-.17-.27-.26-.43-.11.35.05.65.18.98.13.34.3.66.17,1.07l.19.14-.02.05c.09-.01.24.14.28.25-.19.14-.45.05-.4.42-.07.16-.04.36.02.57.08.2.17.45.25.63.03-.21.14-.16.19-.08,0,.19-.17.31-.1.45l-.26.02c.23-.09.25.48.37.54-.2.12-.16-.3-.31-.33.02.75.01.38,0,1.12.16.41.24-.08.48.13.03.36.17.73-.03,1.13l.25-.1c.06.32.03.61,0,.86-.04.25-.16.45-.31.66.12.66.21,1.19.31,1.62.09.41.19.72.29.94.23.42.47.46.73.33.26-.15.49-.48.66-.79.1-.15.15-.3.2-.41.05-.11.07-.18.07-.18.51-1.07.6-1.94.57-2.84-.04-.91-.18-1.87-.28-3.16l-.05-.02Z\"><\/path><path class=\"cls-1\" d=\"M159.96,48.72l-.04.12s.06-.07.04-.12Z\"><\/path><path class=\"cls-1\" d=\"M156.78,49.31c.49,1.1.25,1.58,1.02,2.56.26.52.66,1.02.99,1.49.44.06.38.64.79.78l-.12.22c.15.05.27.13.24.27l-.06.02c.2.07.22.28.34.31l-.06.02.13.16-.08.03c.28.15.42.41.5.66l.19-.14c.01.15.05.26.12.36.02.06.05.09.09.11.01.04.07.06.11.13.2.24.38.47.48.97l-.06.02c.25.13.4.29.52.48.12.19.17.45.26.69.09.24.15.52.28.73.12.21.26.39.47.41-.1-.02-.03.23-.04.3.3.37.57.8.68.03.16.3.1.5.1.84,0-.11.04-.19.08-.2.08-.25.22-.48.33-.65l-.09.23.49-.74c-.06-.15-.07-.31-.11-.47.24-.12.09.63.32.19l-.04-.46c.16-.15.33-.13.49-.11.18.01.39.03.63-.09.42-.47.84-1.05,1.21-1.59l.14-.21.07-.11s.05-.09.05-.09l.15-.25c.09-.17.2-.34.29-.51.39-.68.81-1.3,1.46-1.7l.24.1c.29.18-.16-.6.13-.46l-.02-.23c.07,0,.19-.03.2.07.11-.11.05-.15.04-.3h.27c.5-.38.5-1.02.95-1.47.83-.34,1.38-1.68,1.72-2.49.31-1.23,2.23-1.45,2.49-2.72.07,0,.04-.14,0-.17l.71-.83s3.37-4.05-1.38-2.63l-.03-.07c-.53.37-.79.62-.75,1.19-.4-.23-.33.35-.55.37v-.04c.04.49-.72.42-.68.88-.01-.04-.11-.13-.07-.19-.11.24-.25.58-.46.42-.31.52-.95,1.12-.85,1.68l-.03-.07c.07.36-.17.26-.2.53-.03-.01-.07-.01-.07-.01.07.36-.4.57-.43.8l-.15-.09-.27.41.13-.12c.36.35-.47.11-.43.56-.25.21.41,1.13,0,1.25.1.26-.22-.34-.22-.04-.21-.15-.07-.19-.26-.26-.06.26-.46.14-.48.48l-.17-.1c.06.51-.67.4-.53.82-.11.41-.64-.15-.58.41l-.31-.05c-.14.1.18.29-.04.36-.13-.12-.27.11-.31-.07-.48.2-.25.92-.98,1.11.18.29-.15.41,0,.63-.12-.08-.39.44-.42,0-.01-.04.04-.08.08-.03l-.12-.14c-.5.03-.21.6-.47.82.12-.05.18-.16.22,0l-.21.21-.1-.15-.08.08s-.07.05-.08.03c0,0-.04.02-.07,0,.06.04.1.09.16.13-.05-.02-.15-.09-.2-.11q-.06-.04.02.1c.03.07.1.13.13.16.04.05.07.08.05.13-.07-.01-.16-.06-.22-.1-.06-.04-.11-.11-.13-.12.07.3.05.3.03.37l-.04-.27c0,.45-.08-.61-.07-.25v-.21c0,.21,0,.43,0,.66-.02.35-.04.19-.04.06,0-.13,0-.26-.06.26.03-.1-.02.65-.08.68v-.02s.03-.21.03-.21v-.14c0,.05-.04.15-.03.06.03-.16.06-.48.02-.46.02-.12.04-.25.07-.4-.04.19-.08.38-.13.53.01-.2-.01-.21-.02-.23,0-.02-.02-.06.02-.24,0,0,0-.06-.03-.07,0-.02-.04.02-.14.16.1-.19.13-.31.26-.54-.07.11-.13.18-.16.22-.04.02-.05-.02.02-.12h.02c.06-.14,0-.09-.09-.08h-.02s-.07-.05-.07-.05c-.04-.05-.07-.08-.12-.13-.06-.1-.1-.2-.11-.34-.19.14-.21-.15-.45.05-.51-.29.09-1.11-.83-.78-.15-.17.07-.35.04-.47h.07c-.28-.32-.35-.43-.48-.72-.16-.08-.55.12-.6-.18.19-.01.12-.09.07-.18.06.04.12.04.16-.15-.06.02-.11,0-.14,0,0,0,.02,0,.04-.02-.13-.12-.18-.06-.15.02-.02,0-.06.02-.08.08.1-.28-.27-.43-.01-.62-.32-.43-.79-.61-1.11-.93.11-.13.27-.11.4-.01l-.2-.24c.21-.1.19.09.29.16.12-.5-.7-.49-.62-1.04h-.19s-.01-.02-.01-.02c-.06.02-.21.02-.27-.02.15-.15.38-.22.27-.41.08-.25-.33-.38-.53-.52.04.11-.08.14-.17.13-.05-.09.08-.25-.04-.27l.22-.13c-.18.16-.37-.11-.48-.09.14-.15.22.06.36.02-.23-.36-.12-.19-.36-.54-.28-.1-.18.16-.44.18-.15-.16-.4-.23-.38-.52l-.16.17c-.34-.25-.44-.47-.37-.8-3.05-1.53-2.55.78-2.55.78.12,1.24.98,1.41,1.82,2.49l.04-.06Z\"><\/path><\/g><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a8ed76b e-con-full e-grid e-con e-child\" data-id=\"a8ed76b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-40c6a94 e-con-full e-flex e-con e-child\" data-id=\"40c6a94\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-3252684 e-con-full e-flex e-con e-child\" data-id=\"3252684\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d36e2bf elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"d36e2bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"59\" height=\"88\" viewBox=\"0 0 59 88\" fill=\"none\"><path d=\"M21.207 86.3956L21.1329 86.0066C21.24 85.6278 21.3038 85.2574 21.3244 84.8951C21.3614 84.6193 21.3635 84.395 21.3306 84.2221L21.4233 82.592C21.4603 82.3162 21.4274 82.1433 21.3245 82.0733C21.238 82.0897 21.1866 82.0547 21.1701 81.9683L21.1269 81.0359L21.2566 81.0112L21.4172 80.4432C21.3143 80.3732 21.2546 80.295 21.2381 80.2085C21.3081 80.1056 21.3349 80.0109 21.3184 79.9245L21.3246 79.2514C21.4316 78.8727 21.4769 78.6402 21.4605 78.5537C21.8022 77.0553 22.0492 75.5302 22.2016 73.9783C22.3251 73.686 22.496 72.9368 22.7142 71.7307L22.9736 68.8595C22.9942 68.4972 23.0663 68.17 23.1898 67.8777C23.2968 67.499 23.3606 67.1285 23.3812 66.7663C23.4348 66.5769 23.4286 66.3093 23.3627 65.9636L23.6901 64.1544C23.6407 63.895 23.6695 63.576 23.7765 63.1973C23.7765 63.1973 23.7333 63.2055 23.6469 63.222C23.6469 63.222 23.6386 63.1788 23.6222 63.0923C23.6222 63.0923 23.579 63.1006 23.4925 63.117C23.4925 63.117 23.5007 63.1603 23.5172 63.2467L23.2023 63.7098L22.912 64.3026C22.805 64.6813 22.7679 64.9571 22.8009 65.13C22.6609 65.3358 22.5271 65.8092 22.3995 66.5501L22.3192 66.8342L22.2698 66.5748C22.2533 66.4884 22.2986 66.2558 22.4057 65.8771C22.4057 65.8771 22.3974 65.8339 22.381 65.7474C22.3645 65.661 22.3048 65.5827 22.2019 65.5128L22.1463 65.9265L21.8005 66.9329C21.8005 66.9329 21.7573 66.9412 21.6708 66.9576C21.6708 66.9576 21.6626 66.9144 21.6461 66.828L21.5227 66.1796L21.498 66.0499C21.5144 66.1364 21.4794 66.1878 21.393 66.2043L21.288 66.3587L21.2386 66.0993C21.3375 64.7368 21.3972 63.8744 21.4178 63.5121C21.5248 63.1334 21.5619 62.8576 21.529 62.6847L21.5043 62.5551C21.4178 62.5715 21.3828 62.623 21.3993 62.7094L20.9979 64.1296C21.0308 64.3025 21.0123 64.4404 20.9423 64.5433L20.8682 64.1543L20.8188 63.8949C20.7694 63.6356 20.7653 63.1437 20.8065 62.4192C20.8436 62.1434 20.9156 61.8161 21.0227 61.4374C21.1297 61.0587 21.2203 60.5936 21.2944 60.0419C21.3644 59.939 21.4344 59.8361 21.5044 59.7332C21.5579 59.5439 21.6032 59.3113 21.6403 59.0355L21.5662 58.6465L21.2512 59.1096L21.171 59.3936L20.9054 60.116L20.8498 60.5297C20.8086 61.2542 20.7181 61.7194 20.5781 61.9252L20.4175 62.4933L19.9049 64.7408L19.6888 65.7226C19.6024 65.7391 19.5756 65.8338 19.6085 66.0066L19.5776 66.55L19.448 66.5747L19.4788 66.0313L19.306 65.1237C19.2237 64.6914 19.2093 64.3806 19.2628 64.1913L19.8125 60.7273C19.9524 60.5215 20.1048 59.9102 20.2695 58.8934L20.5165 57.3683C20.5165 57.3683 20.6092 56.6788 20.7945 55.2998C20.848 55.1104 20.8583 54.9293 20.8253 54.7564C20.8624 54.4806 20.9077 54.248 20.9612 54.0587L21.0786 52.5582L21.5109 50.5947L21.4368 50.2057C21.2968 50.4115 21.2351 50.5576 21.2516 50.6441L21.091 51.2121L20.986 51.3665L20.9613 51.2368C21.0684 50.8581 21.1404 50.5308 21.1775 50.255C21.1981 49.8928 21.2269 49.5738 21.264 49.298C21.4039 49.0922 21.5027 48.6702 21.5604 48.0322L21.406 47.9272L21.2764 47.9519L20.6897 49.8104L20.2389 50.9713C20.0083 51.6422 19.7654 52.7187 19.5102 54.2006L19.4299 54.4846L19.5102 54.2006L19.6337 52.0271L19.535 51.5084L19.6461 50.681L20.029 48.4582C20.1402 47.6308 20.2946 46.7951 20.4922 45.9513C20.6899 45.1074 20.8875 44.2635 21.0851 43.4196L21.2581 41.5055C21.5051 40.921 21.7027 40.0771 21.8509 38.9739L22.0115 38.4058C21.9827 37.7842 22.0836 37.138 22.3141 36.467L22.8761 34.4787L24.5991 27.2976L24.9758 25.7478L25.0808 25.5934L24.982 25.0748C24.8091 25.1077 24.6877 25.1756 24.6177 25.2785C23.2634 26.1635 22.3248 26.8797 21.802 27.4272L20.3941 28.5015L19.2209 29.3968C18.7351 29.6685 18.3523 30.0102 18.0723 30.4218L17.4981 30.9343L17.3684 30.959C17.1461 30.7326 16.9568 30.679 16.8003 30.7984C16.5039 31.1236 16.3887 31.4591 16.4545 31.8049L16.5286 32.1939C16.5121 32.1074 16.366 32.0457 16.0902 32.0086C16.0037 32.0251 15.8226 32.0148 15.5468 31.9777C15.271 31.9407 15.0817 31.8871 14.9788 31.8172C14.8059 31.8501 14.668 31.8316 14.5651 31.7616L13.9167 31.885C13.4845 31.9674 12.9987 32.239 12.4594 32.7C12.4759 32.7865 12.3977 32.8462 12.2248 32.8791L10.7984 33.1507L10.7737 33.0211L10.2551 33.1198C9.64993 33.2351 9.04688 33.126 8.44588 32.7925C7.84489 32.4591 7.49294 32.2573 7.39003 32.1874C7.08131 31.9774 6.8055 31.9404 6.56263 32.0762C6.21684 32.142 6.01102 32.0021 5.94517 31.6563C5.89578 31.3969 5.73319 31.2487 5.45739 31.2117C5.06221 31.0182 4.8317 30.7486 4.76585 30.4028C4.55184 29.279 4.733 28.3487 5.30933 27.6118C5.43283 27.3196 5.59133 26.9758 5.78482 26.5807C5.97831 26.1855 6.20679 25.7389 6.47026 25.2408C6.96428 24.0717 7.67028 23.3102 8.58827 22.9562C9.23045 22.5652 9.81295 22.0959 10.3358 21.5485C10.5951 21.4991 10.7948 21.3715 10.9347 21.1657L11.7683 20.6038L13.9604 18.7082L14.7693 18.0167L17.0417 15.8371L19.1041 13.9663C19.6434 13.5052 20.0962 13.0607 20.4626 12.6326C20.9154 12.188 21.4115 11.7352 21.9507 11.2742C22.4036 10.8296 22.8996 10.3768 23.4389 9.91581C23.9617 9.36834 24.571 8.80441 25.2667 8.22401C25.666 7.9688 26.1003 7.66214 26.5696 7.30403C27.1253 6.92945 27.716 6.50342 28.3418 6.02593C29.4368 5.19033 30.1057 4.70461 30.3486 4.56878L32.1949 3.67969C32.5777 3.33803 32.8041 3.11575 32.8741 3.01285C33.6069 2.15665 34.319 1.6627 35.0106 1.53099L35.4737 1.84592L35.3687 2.00029L34.85 2.09906C34.7101 2.30488 34.6915 2.44278 34.7944 2.51277C34.8438 2.7721 34.7389 2.92646 34.4795 2.97585C34.3396 3.18167 34.1914 3.34427 34.0349 3.46364C33.8785 3.58301 33.6871 3.75384 33.4607 3.97612L33.3804 4.26015L33.6644 4.34043L34.0534 4.26635L34.1831 4.24166C34.1666 4.15521 34.1152 4.12022 34.0287 4.13668C34.0123 4.05024 33.9176 4.02348 33.7447 4.0564C33.8311 4.03994 33.8744 4.03171 33.8744 4.03171C33.9443 3.9288 34.0226 3.86911 34.109 3.85265C34.2984 3.90617 34.463 3.83002 34.603 3.6242C34.5701 3.45131 34.64 3.3484 34.8129 3.31548L35.3316 3.2167C35.7309 2.96149 36.0582 3.03354 36.3134 3.43285L36.2084 3.58722C35.8956 3.82596 35.7885 4.20467 35.8873 4.72335C35.9367 4.98269 36.0046 5.10412 36.091 5.08766C36.161 4.98475 36.2475 4.96829 36.3504 5.03827C36.5233 5.00535 36.6097 4.98888 36.6097 4.98888C36.6962 4.97242 36.7312 4.92097 36.7147 4.83452C36.7847 4.73161 36.7682 4.64517 36.6653 4.57519L36.5912 4.18617C36.5748 4.09973 36.6098 4.04828 36.6962 4.03181L36.7209 4.16148C36.7538 4.33437 36.8567 4.40435 37.0296 4.37143L37.184 4.47641C37.2169 4.6493 37.1984 4.7872 37.1284 4.89011C37.1449 4.97655 37.1613 5.063 37.1778 5.14945C37.1078 5.25236 37.1243 5.33881 37.2272 5.40879L37.5112 5.48907L37.9002 5.41499L37.7459 5.31001C37.4371 5.10006 37.4042 4.92717 37.6471 4.79133C37.6471 4.79133 37.7521 4.63697 37.962 4.32825C38.102 4.12243 38.1205 3.98452 38.0176 3.91454L37.9929 3.78487L38.2275 3.60581L38.2522 3.73549L38.7647 4.30975L38.8141 4.56909L38.8388 4.69875L38.9685 4.67406C39.0384 4.57115 39.0652 4.47648 39.0487 4.39003C39.0158 4.21714 39.0343 4.07924 39.1043 3.97632L39.0796 3.84666L39.1043 3.97632C39.1908 3.95986 39.199 4.00309 39.129 4.106C39.3184 4.15952 39.4295 4.27273 39.4625 4.44562C39.5324 4.34271 39.5674 4.29125 39.5674 4.29125C39.6374 4.18835 39.6642 4.09367 39.6477 4.00722C39.6148 3.83433 39.6354 3.47208 39.7095 2.92048C39.693 2.83403 39.7363 2.8258 39.8392 2.89578L40.5616 3.16132C40.6645 3.23131 40.7592 3.25807 40.8456 3.2416C40.9156 3.13869 40.9506 3.08724 40.9506 3.08724L40.9012 2.8279C40.8848 2.74145 40.9115 2.64678 40.9815 2.54387C41.0515 2.44096 41.1729 2.37304 41.3458 2.34011C41.5187 2.30719 41.6216 2.37717 41.6545 2.55007C41.6545 2.55007 41.6628 2.59329 41.6792 2.67974C41.6792 2.67974 41.7225 2.6715 41.8089 2.65504C42.2741 2.74562 42.6342 2.99056 42.8894 3.38987C42.9059 3.47632 42.9656 3.55453 43.0685 3.62452C43.1714 3.6945 43.2661 3.72126 43.3525 3.7048L43.3032 3.44546C43.4225 3.60189 43.5687 3.66364 43.7415 3.63071C43.7909 3.89005 43.7292 4.03619 43.5563 4.06911C43.3299 4.29139 43.1961 4.76478 43.1549 5.48928C43.1549 5.48928 43.1199 5.54073 43.0499 5.64364C43.0664 5.73009 43.2043 5.74862 43.4636 5.69923C43.69 5.47695 43.8362 5.5387 43.902 5.88449C44.0378 6.12736 44.1634 6.55136 44.2786 7.15649C44.4762 8.19384 44.4247 9.09947 44.1241 9.87335C44.0542 9.97626 44.0006 10.1656 43.9636 10.4414C44.013 10.7008 44.0027 10.8819 43.9327 10.9848C43.8956 11.2606 43.7968 11.6825 43.6363 12.2506C43.5457 12.7157 43.3769 13.2406 43.1299 13.8251L42.148 16.4308C41.971 16.9124 41.8022 17.4373 41.6416 18.0053C41.4646 18.487 41.2176 19.0715 40.9006 19.7589C40.8471 19.9483 40.5651 20.5843 40.0546 21.6669C40.0175 21.9427 39.8755 22.3728 39.6285 22.9574C39.575 23.1467 39.3177 23.9124 38.8566 25.2543L37.5289 28.8665L35.7442 34.3125C35.1267 35.7738 34.6203 37.3484 34.225 39.0361C33.8381 39.8264 33.4469 41.0655 33.0517 42.7532C32.7306 43.8894 32.3991 45.2066 32.0574 46.705L31.3349 49.2613C31.1373 50.1052 30.9314 50.9058 30.7173 51.6632C30.5732 52.3177 30.4209 52.929 30.2603 53.4971L29.4513 57.0105C28.9326 58.9905 28.5929 60.2645 28.4324 60.8326C28.21 62.4874 27.9403 63.6585 27.6233 64.3459C27.2939 66.3795 27.0037 67.9128 26.7525 68.9461L26.2646 71.3233C26.207 71.9614 26.0547 72.5726 25.8077 73.1572C25.6471 73.7252 25.538 74.3283 25.4803 74.9664C25.2292 75.9996 24.9389 77.5329 24.6095 79.5665C24.4654 80.221 24.3131 80.8323 24.1525 81.4003C24.0084 82.0549 23.8993 82.6579 23.8252 83.2095L23.7449 83.4935L23.6955 83.2342L24.0476 81.5547C24.1175 81.4518 24.1196 81.2274 24.0538 80.8817C24.0373 80.7952 23.9858 80.7602 23.8994 80.7767L23.64 80.8261L23.5598 81.1101L23.5104 80.8508C23.601 80.3856 23.6895 80.1448 23.7759 80.1283L23.7265 79.869C23.743 79.9554 23.708 80.0069 23.6216 80.0234C23.5351 80.0398 23.4919 80.0481 23.4919 80.0481L23.1893 81.9869L22.9237 82.7093C22.9196 83.158 22.8105 83.7611 22.5964 84.5185L22.4914 84.6729C22.4585 84.5 22.442 84.4135 22.442 84.4135L22.7447 82.4747C22.7117 82.3018 22.722 82.1207 22.7756 81.9313C22.8291 81.742 22.8826 81.5526 22.9361 81.3632L22.862 80.9742L22.8373 80.8446C22.9773 80.6388 23.0391 80.4926 23.0226 80.4062C23.0597 80.1304 23.0967 79.8546 23.1338 79.5788C23.1708 79.303 23.2161 79.0704 23.2696 78.881C23.3767 78.5023 23.4673 78.0372 23.5414 77.4856L23.6217 77.2015C23.6587 76.9257 23.6875 76.6067 23.7081 76.2444C23.8152 75.8657 23.844 75.5467 23.7946 75.2874L23.8749 75.0033L23.9614 74.0463L23.9367 73.9166C24.0602 73.6243 24.2311 72.8751 24.4493 71.669C24.5193 71.5661 24.5028 71.4797 24.3999 71.4097C24.3834 71.3232 24.3752 71.28 24.3752 71.28C24.2023 71.3129 24.1241 71.3726 24.1405 71.4591C23.9841 71.5784 23.8441 71.7843 23.7206 72.0765C23.6671 72.2659 23.6918 72.3956 23.7947 72.4655C23.8441 72.7249 23.842 72.9492 23.7885 73.1386C23.7885 73.1386 23.7103 73.1983 23.5539 73.3176C23.4839 73.4205 23.5518 73.542 23.7576 73.682L23.6527 73.8363C23.3357 74.5238 23.206 75.4891 23.2635 76.7322C23.1936 76.8351 23.175 76.973 23.208 77.1459C23.3273 77.3024 23.352 77.432 23.282 77.5349L22.9424 77.8684L22.9115 78.4117C23.0474 78.6546 23.0103 78.9304 22.8003 79.2391C22.8003 79.2391 22.7304 79.3421 22.5904 79.5479C22.5492 80.2724 22.403 81.1512 22.1519 82.1845L22.0098 83.5552L21.9049 83.7096C21.9049 83.7096 21.8266 83.7693 21.6702 83.8887C21.6002 83.9916 21.6167 84.078 21.7196 84.148C21.5632 84.2674 21.4664 84.465 21.4294 84.7408C21.4952 85.0865 21.5446 85.3459 21.5775 85.5188C21.4911 85.5352 21.4479 85.5435 21.4479 85.5435C21.4643 85.6299 21.5158 85.6649 21.6022 85.6484L21.6269 85.7781C21.5405 85.7946 21.4623 85.8543 21.3923 85.9572C21.3387 86.1465 21.277 86.2927 21.207 86.3956L21.2317 86.5252L21.207 86.3956ZM14.7421 85.6111L14.8718 85.5864C14.8389 85.4136 14.7977 85.1974 14.7483 84.9381C14.6125 84.6952 14.5631 84.4359 14.6002 84.1601C14.5179 83.7278 14.557 83.2277 14.7175 82.6596C14.8575 82.4538 14.8946 82.178 14.8287 81.8322L15.0387 81.5235L15.0881 81.7828C15.1498 82.5773 15.0983 83.4829 14.9336 84.4997L14.8718 85.5864L14.7668 85.7408L14.7421 85.6111ZM16.6131 84.8517C16.4402 84.8846 16.3373 84.8147 16.3044 84.6418L16.397 83.0117L16.502 82.8573L16.5267 82.987L16.7058 83.2216C16.8087 83.2916 16.8251 83.378 16.7552 83.4809L16.6934 84.5677L16.6131 84.8517ZM15.2301 80.4121C15.1807 80.1527 15.1931 79.7472 15.2672 79.1956C15.3207 79.0063 15.3228 78.7819 15.2734 78.5226C15.3434 78.4197 15.3619 78.2818 15.329 78.1089C15.329 78.1089 15.3722 78.1007 15.4587 78.0842C15.4587 78.0842 15.4504 78.041 15.434 77.9545L15.4834 78.2139L15.5328 78.4732C15.5821 78.7326 15.5615 79.0948 15.471 79.56C15.3804 80.0251 15.3516 80.3441 15.3845 80.517L15.2795 80.6714L15.2301 80.4121ZM16.4094 81.6656L16.4403 81.1222L16.4712 80.5788L16.4218 80.3195C16.4383 80.4059 16.4033 80.4574 16.3169 80.4738C16.3333 80.5603 16.2983 80.6117 16.2119 80.6282L16.1872 80.4985L16.428 79.6464L16.6874 79.5971L16.7121 79.7267C16.7985 79.7103 16.8335 79.6588 16.8171 79.5724L16.9591 78.2016L17.0641 78.0472L17.1135 78.3066L16.959 81.0234C16.8026 81.1428 16.7326 81.2457 16.7491 81.3321C16.7655 81.4186 16.7388 81.5133 16.6688 81.6162C16.6852 81.7026 16.6503 81.7541 16.5638 81.7705L16.4094 81.6656ZM16.2799 78.8684C16.177 78.7984 16.1091 78.677 16.0761 78.5041C16.0761 78.5041 16.0597 78.4177 16.0267 78.2448C16.0967 78.1419 16.0453 78.1069 15.8724 78.1398L15.928 77.7261C15.9115 77.6396 15.895 77.5532 15.8786 77.4668C15.965 77.4503 16 77.3988 15.9836 77.3124C16 77.3988 16.0597 77.477 16.1626 77.547C16.2655 77.617 16.317 77.652 16.317 77.652L16.3664 77.9113C16.3993 78.0842 16.4507 78.1192 16.5207 78.0163L16.5454 78.146L16.5392 78.819L16.2799 78.8684ZM16.7679 73.6693C16.7185 73.41 16.7473 73.091 16.8544 72.7123C16.9243 72.6094 17.0026 72.5497 17.089 72.5332L17.1137 72.6629C16.9737 72.8687 16.8585 73.2042 16.7679 73.6693ZM24.5604 70.8416L24.4308 70.8663C24.2579 70.8992 24.1797 70.9589 24.1961 71.0454L24.3505 71.1503L24.5604 70.8416ZM20.8619 67.6492C20.9484 67.6327 20.9916 67.6245 20.9916 67.6245C20.9751 67.538 20.9669 67.4948 20.9669 67.4948C21.0369 67.3919 21.0636 67.2972 21.0472 67.2108C21.0307 67.1243 21.1007 67.0214 21.2571 66.902L21.2818 67.0317C21.0719 67.3404 20.9916 67.6245 21.041 67.8838L20.9113 67.9085L20.8619 67.6492ZM24.3814 70.607C24.4514 70.5041 24.5296 70.4444 24.616 70.4279C24.686 70.325 24.7128 70.2303 24.6963 70.1439C24.7334 69.8681 24.7704 69.5923 24.8075 69.3165C24.8446 69.0407 24.8816 68.7649 24.9187 68.4891L24.894 68.3594C24.861 68.1865 24.7746 68.203 24.6346 68.4088L24.3753 68.4582L24.4 68.5878C24.5523 68.9172 24.5667 69.228 24.4432 69.5202C24.3897 69.7096 24.3711 69.8475 24.3876 69.9339C24.4041 70.0204 24.3691 70.0718 24.2826 70.0883C24.0933 70.0348 24.0233 70.1377 24.0727 70.397L24.3814 70.607ZM20.2507 66.5562C20.3206 66.4533 20.3474 66.3586 20.3309 66.2722C20.298 66.0993 20.3166 65.9614 20.3865 65.8585C20.3701 65.772 20.3618 65.7288 20.3618 65.7288C20.4483 65.7123 20.4915 65.7041 20.4915 65.7041C20.5244 65.877 20.5409 65.9635 20.5409 65.9635L20.5347 66.6365C20.4483 66.653 20.4133 66.7044 20.4297 66.7909L20.2507 66.5562ZM24.8446 68.1001L25.1348 67.5073L25.1101 67.3776C25.1101 67.3776 25.0669 67.3859 24.9805 67.4023C24.9805 67.4023 24.9887 67.4455 25.0051 67.532C25.0051 67.532 24.9002 67.6864 24.6902 67.9951L24.7149 68.1248L24.8446 68.1001ZM33.6453 20.4687L34.1455 19.5673C34.059 19.5837 33.9993 19.5055 33.9664 19.3326C33.9829 19.4191 33.9561 19.5137 33.8861 19.6167C33.9026 19.7031 33.8408 19.8492 33.7009 20.055C33.5609 20.2609 33.4477 20.372 33.3613 20.3885L33.386 20.5181L33.6453 20.4687ZM34.232 18.6102L34.1023 18.6349C33.7565 18.7007 33.6001 18.8201 33.633 18.993C33.6659 19.1659 33.8121 19.2276 34.0714 19.1783L34.232 18.6102ZM34.4975 17.8878C34.5346 17.612 34.6581 17.3197 34.868 17.011L35.0286 16.4429C34.9092 16.2865 34.9277 16.1486 35.0842 16.0292L35.3188 15.8501L35.1397 15.6155C35.1397 15.6155 35.1048 15.6669 35.0348 15.7699C34.9483 15.7863 34.9133 15.8378 34.9298 15.9242C34.7569 15.9571 34.6952 16.1033 34.7445 16.3626C34.6375 16.7413 34.5058 16.9904 34.3493 17.1097C34.2629 17.1262 34.2361 17.2209 34.269 17.3938C34.372 17.4638 34.3967 17.5934 34.3431 17.7828C34.2731 17.8857 34.1867 17.9022 34.0838 17.8322C34.0838 17.8322 34.092 17.8754 34.1085 17.9618C34.1085 17.9618 34.0653 17.9701 33.9788 17.9865L34.1085 17.9618L34.2382 17.9371L34.2628 18.0668L34.4975 17.8878ZM35.4609 14.4794C35.6008 14.2735 35.7573 14.1542 35.9302 14.1212C35.9302 14.1212 35.8869 14.1295 35.8005 14.1459C35.6976 14.076 35.6379 13.9977 35.6214 13.9113L35.4362 14.3497L35.4609 14.4794ZM39.178 15.6527C39.1615 15.5662 39.1101 15.5313 39.0236 15.5477L38.7087 16.0108L38.7581 16.2701L38.8878 16.2454L39.178 15.6527ZM39.7647 13.7941C39.7647 13.7941 39.8346 13.6912 39.9746 13.4854L40.0549 13.2014L39.9252 13.2261L39.8203 13.3804L39.74 13.6645L39.7647 13.7941ZM33.1765 6.71768C33.3494 6.68475 33.4709 6.61683 33.5408 6.51392C33.6973 6.39455 33.8537 6.27518 34.0101 6.15581C34.1666 6.03644 34.3662 5.90883 34.6091 5.773C34.782 5.74008 34.9466 5.66393 35.1031 5.54456C35.2595 5.42518 35.3809 5.35726 35.4674 5.3408L35.702 5.16174C35.702 5.16174 35.6588 5.16997 35.5724 5.18644C35.5559 5.09999 35.5394 5.01355 35.523 4.9271C35.4365 4.94356 35.3768 4.86535 35.3439 4.69245L35.2945 4.43312L35.0599 4.61217L35.0537 5.28521C34.9672 5.30168 34.9322 5.35313 34.9487 5.43957L34.8746 5.05057C34.8582 4.96413 34.8499 4.9209 34.8499 4.9209C34.9364 4.90444 34.9796 4.89621 34.9796 4.89621C34.9467 4.72331 34.9302 4.63687 34.9302 4.63687C34.9137 4.55042 34.8191 4.52366 34.6462 4.55659C34.4733 4.58951 34.3518 4.65743 34.2819 4.76034L34.2572 4.63067C34.1707 4.64713 34.0925 4.70682 34.0225 4.80972C34.0225 4.80972 33.9793 4.81795 33.8929 4.83442C33.7364 4.95379 33.6129 5.24605 33.5223 5.71121C33.4153 6.08992 33.2918 6.38219 33.1518 6.588L33.1765 6.71768ZM41.0121 10.466C41.0121 10.466 41.1171 10.3116 41.327 10.0029L41.1726 9.89794L40.9627 10.2067L41.0121 10.466Z\" fill=\"#70C7D8\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c10daf elementor-widget elementor-widget-heading\" data-id=\"6c10daf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Bewustmaken\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a595d8 elementor-widget elementor-widget-text-editor\" data-id=\"7a595d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>We willen afstappen van de reflex om te zeggen: \u201eDat is normaal, dat hoort bij de leeftijd.\u201c Artrose kan sporters, mensen met overgewicht, mensen met een fysiek zwaar beroep of mensen met een zeer zittend leven treffen, en dat op heel verschillende momenten in hun leven.  <\/p><p>Door deze diversiteit te verklaren, wordt al een deel van het schuldgevoel en het fatalisme weggenomen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-90a9b2a e-con-full e-flex e-con e-child\" data-id=\"90a9b2a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-ef150a6 e-con-full e-flex e-con e-child\" data-id=\"ef150a6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8e8c1e7 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"8e8c1e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"64\" height=\"80\" viewBox=\"0 0 64 80\" fill=\"none\"><path d=\"M21.7446 77.2197C21.6046 77.4255 21.5099 77.3987 21.4605 77.1394C21.3247 76.8965 21.1354 76.843 20.8925 76.9788L20.7628 77.0035C20.5199 77.1394 20.3038 77.1805 20.1145 77.127C20.0115 77.057 19.8922 76.9006 19.7563 76.6577C19.7234 76.4848 19.6205 76.4148 19.4476 76.4477C19.0689 76.3407 18.8363 76.2954 18.7499 76.3119L18.7252 76.1822L18.188 75.4783C17.9822 75.3383 17.8525 75.363 17.799 75.5524C17.729 75.6553 17.5911 75.6367 17.3853 75.4968C17.2824 75.4268 17.128 75.3218 16.9222 75.1818C16.8193 75.1119 16.6732 75.0501 16.4838 74.9966C16.3974 75.013 16.3377 74.9348 16.3048 74.7619C16.3747 74.659 16.3418 74.4861 16.206 74.2433C16.206 74.2433 16.1031 74.1733 15.8973 74.0333C15.8643 73.8604 15.7285 73.6175 15.4897 73.3047L15.4157 72.9157C15.3827 72.7428 15.3231 72.6646 15.2366 72.681C15.1337 72.611 14.9958 72.5925 14.8229 72.6254L13.7609 72.6933L13.6312 72.718C13.5983 72.5451 13.4707 72.3455 13.2484 72.1191C13.0261 71.8926 12.9417 71.6848 12.9952 71.4954C12.9129 71.0632 12.8038 70.7256 12.668 70.4827C12.6351 70.3098 12.5322 70.2399 12.3593 70.2728L11.9703 70.3469C11.7809 70.2933 11.6348 70.2316 11.5319 70.1616C11.499 69.9887 11.5093 69.8076 11.5628 69.6182C11.6328 69.5153 11.6431 69.3342 11.5937 69.0749L11.427 67.4941C11.3447 67.0619 11.4744 67.0372 11.816 67.4201C11.9889 67.3871 12.0671 67.3274 12.0507 67.241L12.026 67.1113L11.563 63.9746L11.3654 62.9372L11.4457 62.6532L11.6248 62.8878L11.6186 63.5609L11.7976 63.7955L11.7482 63.5362L11.8903 62.1654C11.9809 61.7002 11.88 61.4059 11.5878 61.2824C11.4849 61.2124 11.4252 61.1342 11.4087 61.0477C11.4787 60.9448 11.5569 60.8851 11.6434 60.8687L11.7483 60.7143C11.8183 60.6114 11.8451 60.5167 11.8286 60.4303C11.7957 60.2574 11.8142 60.1195 11.8842 60.0166C11.8348 59.7572 11.8637 59.4382 11.9707 59.0595L12.0572 58.1024C11.9131 56.8757 12.082 55.4103 12.5637 53.7061C12.7942 53.0351 13.0083 52.2777 13.2059 51.4338C13.49 50.5735 13.8173 49.7049 14.1878 48.8281C15.5257 45.9755 16.3615 44.2486 16.6949 43.6476L19.2452 39.3995C19.5087 38.9015 19.8236 38.4384 20.19 38.0103C20.5399 37.4957 20.8734 36.8947 21.1904 36.2073L23.2096 33.404C24.0123 32.4449 24.7122 31.4158 25.3091 30.3168C25.9719 29.5635 26.3568 28.9975 26.4638 28.6188L28.0632 26.433C28.656 25.7826 29.0923 25.2516 29.3723 24.84C29.5822 24.5312 29.7839 24.1793 29.9774 23.7841C30.2574 23.3725 30.5291 22.9176 30.7925 22.4195C31.5253 21.5633 32.0337 20.7051 32.3178 19.8447C32.6677 19.3302 32.8427 19.0729 32.8427 19.0729L32.9229 18.7889L32.7933 18.8136C32.1511 19.2046 31.5707 19.4495 31.052 19.5483C30.1505 19.9887 29.1357 20.5403 28.0078 21.203C27.7649 21.3389 27.2277 21.5755 26.3962 21.913C25.6511 22.2341 24.9677 22.409 24.3461 22.4378C23.8275 22.5366 23.4302 22.5675 23.1544 22.5304L22.6357 22.6292L22.0677 22.4686C21.8619 22.3286 21.5861 22.2916 21.2403 22.3574C20.808 22.4397 20.489 22.4109 20.2832 22.271L20.1535 22.2956C19.9806 22.3286 19.6637 22.0754 19.2027 21.5361C19.0997 21.4661 19.0483 21.4312 19.0483 21.4312C19.1183 21.3282 19.11 21.285 19.0236 21.3015C18.7478 21.2644 18.507 21.1759 18.3012 21.0359C18.0789 20.8095 17.9163 20.6613 17.8134 20.5913C17.5911 20.3649 17.4038 20.0871 17.2515 19.7577C17.0992 19.4284 17.0066 19.1773 16.9737 19.0044C16.4468 18.1194 15.9611 17.4504 15.5165 16.9976C15.4136 16.9276 15.3375 16.7629 15.2881 16.5036C15.2387 16.2443 15.1543 16.0364 15.0349 15.8799L14.5534 14.7623C14.6933 14.5565 14.6769 14.47 14.504 14.503C14.1582 14.5688 13.9256 14.5235 13.8062 14.3671C13.6704 14.1242 13.6642 13.8567 13.7877 13.5644C13.9648 13.0828 14.4382 12.276 15.208 11.144C15.348 10.9381 15.5662 10.6726 15.8626 10.3474C16.159 10.0223 16.3339 9.76498 16.3874 9.57563C16.7373 9.06108 17.0584 8.86556 17.3507 8.98907C17.3507 8.98907 17.4372 8.97261 17.61 8.93968C17.6965 8.92322 17.7829 8.90676 17.8694 8.89029C17.9394 8.78738 18.069 8.76269 18.2584 8.81621L20.685 9.56344C21.8911 9.78166 22.7371 9.75493 23.2228 9.48326C23.795 9.19513 24.3755 8.95022 24.9641 8.74854C25.6228 8.44394 26.2382 8.14758 26.8104 7.85945C27.3826 7.57132 27.963 7.32641 28.5517 7.12472C29.1239 6.83659 29.6961 6.54846 30.2683 6.26033L33.7015 4.53154C34.5166 4.10757 34.9673 3.88736 35.0538 3.87089C35.3131 3.82151 35.6239 3.80711 35.9861 3.82771C36.4184 3.74539 36.8856 3.61163 37.3878 3.4264C37.8736 3.15474 38.2296 2.90776 38.4561 2.68548C38.596 2.47966 38.8039 2.39528 39.0797 2.43234C39.3391 2.38295 39.512 2.35002 39.5984 2.33356C40.0306 2.25125 40.325 2.15041 40.4814 2.03104C40.5514 1.92813 40.716 1.85198 40.9754 1.80259C41.3212 1.73674 41.6999 1.84378 42.1115 2.12371C42.3338 2.35013 42.6014 2.34396 42.9142 2.10522C43.4329 2.00645 43.9763 2.03734 44.5443 2.1979L45.2421 2.33377C45.6743 2.25145 46.053 2.3585 46.3782 2.6549C46.3947 2.74134 46.4544 2.81956 46.5573 2.88954C46.6437 2.87308 46.6952 2.90807 46.7116 2.99452C46.971 2.94513 47.2035 2.99042 47.4094 3.13039L48.2368 3.24156C48.2368 3.24156 48.2882 3.27655 48.3911 3.34654C48.4776 3.33008 48.529 3.36507 48.5455 3.45151C48.5084 3.72731 48.7122 4.09163 49.1568 4.54446C49.2926 4.78733 49.4799 5.0652 49.7186 5.37806C50.0273 5.58801 50.2496 5.81443 50.3855 6.05731L50.5151 6.03261C51.149 6.53896 51.4536 7.1976 51.4289 8.00855C51.4454 8.09499 51.573 8.29465 51.8117 8.60751C52.0505 8.92037 52.0566 9.18794 51.8302 9.41022C51.6738 9.52959 51.6985 9.65926 51.9043 9.79923L52.213 10.0092C52.3159 10.0792 52.3242 10.1224 52.2377 10.1388C52.2706 10.3117 52.2089 10.4579 52.0525 10.5772C51.9825 10.6802 51.9125 10.7831 51.8425 10.886L51.8919 11.1453L51.861 11.6887L51.9351 12.0777C52.0545 12.2341 52.0359 12.372 51.8795 12.4914L51.9042 12.6211C51.9865 13.0533 51.9412 13.2859 51.7683 13.3188L51.5028 14.0412L51.3175 14.4796L51.3422 14.6093C51.0829 14.6587 50.9347 14.8213 50.8976 15.0971C50.8441 15.2864 50.8256 15.4243 50.842 15.5108C50.4551 16.3011 50.1484 16.8074 49.922 17.0297C49.5679 17.993 49.2509 18.6804 48.971 19.092L47.5507 21.5125L45.797 23.5933L43.7222 26.8102C43.1294 27.4606 42.6663 28.0863 42.3328 28.6873C41.9829 29.2018 41.6247 29.6732 41.2584 30.1013C38.4796 33.8554 37.0902 35.7324 37.0902 35.7324C35.6906 37.7906 34.5544 39.3507 33.6816 40.4127C33.6816 40.4127 32.5969 42.0078 30.4274 45.198L28.0067 49.4214C27.027 50.8621 26.1234 52.4675 25.2959 54.2376L24.1041 57.152C23.3466 58.8191 22.8484 60.4369 22.6096 62.0052L22.5293 62.2893C22.5458 62.3757 22.6405 62.4025 22.8133 62.3696C23.0192 62.5095 23.2085 62.563 23.3814 62.5301C23.3979 62.6166 23.579 62.6269 23.9248 62.561C24.0977 62.5281 24.1491 62.5631 24.0791 62.666C23.9927 62.6824 23.9577 62.7339 23.9742 62.8203L24.1038 62.7957L24.6719 62.9562C24.8448 62.9233 24.9312 62.9068 24.9312 62.9068L25.0856 63.0118C25.4314 62.946 25.7504 62.9748 26.0427 63.0983C26.3185 63.1353 26.6211 63.0777 26.9504 62.9254C27.0204 62.8225 27.4279 62.6105 28.173 62.2895C28.313 62.0837 28.4426 62.059 28.562 62.2154C28.7514 62.2689 29.0457 62.1681 29.445 61.9129C31.4539 61.172 32.9523 60.5731 33.9402 60.1162L36.3855 58.8443C36.7313 58.7784 37.147 58.6097 37.6328 58.338L39.3741 57.6033L39.5037 57.5786L39.3988 57.733C38.8965 57.9182 38.3676 58.1981 37.8118 58.5727C37.499 58.8114 37.1779 59.0069 36.8486 59.1592C36.5192 59.3115 36.1899 59.4638 35.8606 59.6161C35.6342 59.8384 35.1217 60.2047 34.323 60.7152L34.1934 60.7399L34.323 60.7152L34.8417 60.6164L34.3477 60.8448C33.3927 61.4746 32.5262 61.8636 31.7482 62.0117L30.8096 62.728L30.5749 62.907C30.5749 62.907 30.5832 62.9503 30.5996 63.0367C30.5996 63.0367 30.6428 63.0285 30.7293 63.012L32.2359 62.4563C32.5488 62.2176 32.7917 62.0818 32.9646 62.0488L34.8108 61.1598L35.6444 60.5979C35.8709 60.3756 36.3298 60.1986 37.0214 60.0669C37.0214 60.0669 37.1079 60.0504 37.2808 60.0175C37.2808 60.0175 37.2375 60.0258 37.1511 60.0422C37.1511 60.0422 37.1593 60.0854 37.1758 60.1719L36.8609 60.635L36.1569 61.1722L35.9223 61.3512L36.1816 61.3018C36.441 61.2524 36.6488 61.1681 36.8053 61.0487L37.0893 61.129C37.1593 61.0261 37.2025 61.0178 37.219 61.1043C37.3054 61.0878 37.3919 61.0713 37.4783 61.0549L37.219 61.1043C37.2354 61.1907 37.2004 61.2422 37.114 61.2586L37.2437 61.2339L37.787 61.2648L38.176 61.1908L40.93 60.1288C41 60.0259 41.1646 59.9497 41.424 59.9004C41.494 59.7974 41.6154 59.7295 41.7883 59.6966C41.9612 59.6637 42.0826 59.5958 42.1526 59.4929C43.6593 58.9372 44.4126 58.6594 44.4126 58.6594C44.8983 58.3877 45.2709 58.2272 45.5302 58.1778C45.7731 58.0419 46.0324 57.9925 46.3082 58.0296C46.5676 57.9802 46.8187 57.8876 47.0616 57.7518C47.3209 57.7024 47.5453 57.7044 47.7346 57.758C48.772 57.5604 49.585 57.3608 50.1736 57.1591L50.4577 57.2394C50.6306 57.2065 50.8117 57.2168 51.001 57.2703C51.2768 57.3073 51.5012 57.3094 51.6741 57.2765L51.9334 57.2271L51.8284 57.3815C51.602 57.6037 51.3674 57.7828 51.1245 57.9186C50.9516 57.9516 50.8219 57.9763 50.7355 57.9927L50.6305 58.1471L50.9146 58.2274L51.6926 58.0792L51.9519 58.0298L51.8469 58.1842L51.8716 58.3138L52.0013 58.2892C52.0878 58.2727 52.1742 58.2562 52.2606 58.2398C52.3306 58.1369 52.4171 58.1204 52.52 58.1904C52.52 58.1904 52.6064 58.1739 52.7793 58.141C53.0922 57.9022 53.3351 57.7664 53.508 57.7335C53.5779 57.6306 53.6212 57.6223 53.6376 57.7088C53.7241 57.6923 53.7323 57.7356 53.6623 57.8385C53.7117 58.0978 53.8228 58.211 53.9957 58.1781C54.288 58.3016 54.4074 58.458 54.3539 58.6474C54.3539 58.6474 54.3621 58.6906 54.3785 58.777C54.3785 58.777 54.4218 58.7688 54.5082 58.7523L54.7676 58.703L54.8972 58.6783C54.8808 58.5918 54.8293 58.5568 54.7429 58.5733L54.7182 58.4436L54.8478 58.4189C54.9343 58.4025 55.0804 58.4642 55.2862 58.6042C55.4756 58.6577 55.6402 58.5816 55.7802 58.3757L55.9099 58.351L55.8049 58.5054L55.595 58.8141L55.8296 58.6351L56.0889 58.5857C56.1589 58.4828 56.2804 58.4149 56.4533 58.3819C56.3668 58.3984 56.3318 58.4499 56.3483 58.5363C56.4512 58.6063 56.4677 58.6927 56.3977 58.7956C55.6608 60.1005 54.8498 61.0164 53.9647 61.5433L53.5201 62.0311C52.9644 62.4057 52.4004 62.737 51.8282 63.0251C51.326 63.2104 50.8753 63.4306 50.476 63.6858L49.1484 64.4761C48.9755 64.509 48.7676 64.5934 48.5247 64.7292C48.2654 64.7786 47.9793 64.9227 47.6664 65.1614C47.3206 65.2273 46.9131 65.4393 46.4438 65.7974C46.2009 65.9332 45.9066 66.0341 45.5608 66.0999C45.215 66.1658 44.9639 66.2584 44.8075 66.3777C44.1488 66.6823 43.6199 66.9622 43.2206 67.2174C42.8212 67.4727 42.4219 67.7279 42.0226 67.9831C41.6069 68.1518 41.1993 68.3638 40.8 68.619C40.8 68.619 40.7568 68.6272 40.6703 68.6437C40.6539 68.5573 40.6374 68.4708 40.621 68.3844L40.4913 68.4091L40.0467 68.8968L39.0587 69.3537C38.7994 69.4031 38.5483 69.4957 38.3054 69.6316C38.149 69.7509 37.9411 69.8353 37.6817 69.8847L37.4471 70.0638C37.4471 70.0638 37.4553 70.107 37.4718 70.1934C37.4718 70.1934 37.4286 70.2017 37.3421 70.2181L37.0828 70.2675C36.8234 70.3169 36.5723 70.4095 36.3295 70.5454C36.0866 70.6812 35.8869 70.8088 35.7305 70.9282L35.6255 71.0825L35.7552 71.0578C35.7717 71.1443 35.8231 71.1793 35.9096 71.1628L35.7799 71.1875C35.0513 71.595 34.2629 71.9243 33.4149 72.1754C33.345 72.2783 33.1803 72.3544 32.921 72.4038C32.6616 72.4532 32.5402 72.5211 32.5566 72.6076L32.322 72.7866C30.9882 73.3094 30.2781 73.579 30.1917 73.5954L29.0988 74.2067C28.2837 74.6307 27.3575 74.9414 26.3201 75.139C26.1637 75.2583 25.151 75.5856 23.2821 76.1206C23.1092 76.1536 22.9878 76.2215 22.9178 76.3244C22.8478 76.4273 22.7346 76.5384 22.5782 76.6578L22.1089 77.0159C22.006 76.9459 21.9195 76.9624 21.8496 77.0653C21.866 77.1517 21.831 77.2032 21.7446 77.2197ZM15.2868 50.3657C15.4268 50.1598 15.5235 49.9623 15.5771 49.7729C15.7006 49.4806 15.7973 49.283 15.8673 49.1801C15.9373 49.0772 16.0237 49.0608 16.1266 49.1307L16.3057 49.3654L16.2007 49.5198C16.1143 49.5362 16.071 49.5445 16.071 49.5445C16.0546 49.458 16.0464 49.4148 16.0464 49.4148L16.0217 49.2851L15.892 49.3098C15.9249 49.4827 15.9064 49.6206 15.8364 49.7235L15.9661 49.6988C15.8261 49.9046 15.7561 50.0075 15.7561 50.0075C15.6162 50.2134 15.5029 50.3245 15.4165 50.341C15.433 50.4274 15.398 50.4789 15.3115 50.4953L15.2868 50.3657ZM16.9171 47.6365L17.0776 47.0684L17.2567 47.3031L16.9417 47.7662L16.9171 47.6365ZM16.9788 46.5498L17.584 45.4939C17.6005 45.5803 17.5387 45.7265 17.3987 45.9323L17.0035 46.6794L16.7936 46.9882L16.9788 46.5498ZM16.9048 46.1607L17.4049 45.2593L17.5346 45.2346L17.4296 45.3889C17.3226 45.7676 17.1909 46.0167 17.0344 46.1361C17.0509 46.2225 17.0159 46.274 16.9294 46.2904L16.9048 46.1607ZM13.2242 57.8802L13.3848 57.3121C13.3683 57.2257 13.3868 57.0878 13.4404 56.8984C13.4939 56.7091 13.4609 56.5362 13.3416 56.3797C13.3251 56.2933 13.4033 56.2336 13.5762 56.2007C13.6791 56.2707 13.7306 56.3057 13.7306 56.3057C13.8006 56.2028 13.8273 56.1081 13.8109 56.0216L14.132 54.8855L14.5272 54.1384C14.5972 54.0355 14.5807 53.949 14.4778 53.879C14.4614 53.7926 14.4963 53.7411 14.5828 53.7247C14.7063 53.4324 14.8998 53.0372 15.1633 52.5391C15.4267 52.0411 15.577 51.6541 15.6141 51.3783C16.4209 49.9705 16.9129 49.0258 17.0899 48.5442L18.3805 46.1485L18.6152 45.9694C18.8251 45.6607 18.9054 45.3766 18.856 45.1173L18.8313 44.9876L18.7016 45.0123L18.7263 45.142L18.7016 45.0123C18.7758 44.4607 18.9692 44.0655 19.2821 43.8268L20.3072 42.1535L22.5179 38.2388C22.5014 38.1524 22.5364 38.1009 22.6228 38.0844L22.2338 38.1585L22.2832 38.4179C22.2297 38.6072 22.1515 38.6669 22.0486 38.5969C21.8757 38.6299 21.8057 38.7328 21.8386 38.9057C21.9415 38.9756 21.958 39.0621 21.888 39.165C21.8509 39.4408 21.7274 39.7331 21.5175 40.0418C21.2911 40.2641 21.0996 40.4349 20.9432 40.5543C20.8732 40.6572 20.76 40.7683 20.6036 40.8877C20.5336 40.9906 20.4719 41.1367 20.4183 41.3261L19.3192 42.6104L18.3188 44.4134C18.3188 44.4134 18.0739 44.7735 17.584 45.4939L18.0595 44.4627C18.2694 44.154 18.3929 43.8618 18.43 43.586C18.5535 43.2937 18.6852 43.0446 18.8252 42.8388C19.488 42.0855 19.9779 41.3652 20.2949 40.6777C20.2949 40.6777 20.9597 39.7001 22.2894 37.7448C23.5491 35.8925 24.179 34.9663 24.179 34.9663L24.2592 34.6823C24.0864 34.7152 24.0081 34.7749 24.0246 34.8613C24.0246 34.8613 23.9196 35.0157 23.7097 35.3244L22.7402 36.584L22.0054 37.6645C21.2726 38.5207 20.6428 39.4469 20.1158 40.4431C20.0294 40.4596 19.9162 40.5707 19.7762 40.7765L19.9614 40.3381L21.4867 37.7633L21.5917 37.609C21.5052 37.6254 21.4702 37.6769 21.4867 37.7633C20.4905 39.1176 19.8256 40.0952 19.4922 40.6962L17.1024 44.3763L15.0461 48.3959C14.902 49.0504 14.6714 49.7214 14.3544 50.4088C14.1074 50.9934 13.9119 51.6129 13.7678 52.2674C13.5043 52.7655 13.422 53.2739 13.5207 53.7926L13.1996 54.9287C13.1626 55.2045 13.1255 55.4803 13.0884 55.7561C13.0349 55.9454 12.9814 56.1348 12.9279 56.3242L13.002 56.7132L13.076 57.1022C13.0225 57.2915 13.0287 57.5591 13.0945 57.9049L12.9896 58.0592L13.2242 57.8802ZM39.269 60.5795L40.2323 59.9929L40.5163 60.0732L40.257 60.1226L39.2937 60.7092L39.269 60.5795ZM36.6757 58.2515C36.5893 58.268 36.5893 58.268 36.6757 58.2515C36.7457 58.1486 36.7807 58.0972 36.7807 58.0972L37.4846 57.56C37.4846 57.56 37.4928 57.6032 37.5093 57.6897C37.5093 57.6897 37.5525 57.6814 37.639 57.665L37.3796 57.7144L36.8054 58.2268L36.6757 58.2515ZM39.1702 60.0608L39.1455 59.9311C39.3884 59.7953 39.6313 59.6595 39.8741 59.5236C40.2035 59.3713 40.4978 59.2705 40.7571 59.2211L40.8868 59.1964L40.7818 59.3508L39.2999 60.0361L39.1702 60.0608ZM40.0224 57.4798C39.8166 57.3399 39.7137 57.2699 39.7137 57.2699L39.8187 57.1155L40.467 56.992C40.8128 56.9262 41.1421 56.7739 41.455 56.5351L41.7143 56.4858L41.739 56.6154C40.8375 57.0559 40.2653 57.344 40.0224 57.4798ZM43.857 54.3309L44.5857 53.9234L44.6103 54.053L43.857 54.3309ZM53.2362 59.129L53.0819 59.024L52.7422 59.3574L52.2729 59.7155L52.1433 59.7402L52.4273 59.8205L53.2362 59.129ZM45.444 53.4912L45.5489 53.3368L46.6666 52.8552C46.7365 52.7523 46.8312 52.7791 46.9506 52.9355L46.5616 53.0096L45.4686 53.6208L45.444 53.4912Z\" fill=\"#70C7D8\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb7b38f elementor-widget elementor-widget-heading\" data-id=\"fb7b38f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Onderwijzen<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34bd4e8 elementor-widget elementor-widget-text-editor\" data-id=\"34bd4e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p> Een deel van de mensen lijdt aan artrose die als \u201emoeilijk te behandelen\u201c of \u201erefractair\u201c wordt beschouwd: de pijn houdt aan, de reacties op behandelingen zijn beperkt en het dagelijks leven blijft zwaar. <\/p><p>Het is niet onze bedoeling om er nog een label bij te plakken, maar om uit te leggen wat deze situaties inhouden, waarom ze voorkomen en hoe we hier beter rekening mee kunnen houden in de dialoog met zorgverleners.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-067d707 e-con-full e-flex e-con e-child\" data-id=\"067d707\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-fee6de7 e-con-full e-flex e-con e-child\" data-id=\"fee6de7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cddac2d elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"cddac2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Beweging centraal stellen<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5dcd534 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"5dcd534\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"75\" height=\"86\" viewBox=\"0 0 75 86\" fill=\"none\"><path d=\"M26.5733 83.2584C25.6224 83.4395 24.69 83.4826 23.7761 83.3879C23.241 83.4003 22.4218 83.3323 21.3186 83.1841L20.4912 83.0729C18.8735 82.5747 17.8238 82.2372 17.3422 82.0601C16.5847 81.846 15.3128 81.282 13.5263 80.3681L13.2175 80.1582L13.0385 79.9235C13.2114 79.8906 13.2978 79.8741 13.2978 79.8741C13.4707 79.8412 13.6086 79.8597 13.7115 79.9297C13.8144 79.9997 13.9523 80.0182 14.1252 79.9853C14.2117 79.9689 14.3063 79.9956 14.4093 80.0656C14.8909 80.2426 15.3993 80.325 15.9344 80.3126C15.9509 80.3991 16.0455 80.4258 16.2184 80.3929L16.6321 80.4485C17.0108 80.5556 17.3299 80.5844 17.5892 80.535C17.6057 80.6214 17.6489 80.6132 17.7189 80.5103C17.7024 80.4239 17.651 80.3889 17.5645 80.4053C17.548 80.3189 17.5398 80.2757 17.5398 80.2757C17.4534 80.2921 17.4101 80.3003 17.4101 80.3003L17.3608 80.041C17.3443 79.9546 17.4225 79.8949 17.5954 79.8619C17.6819 79.8455 17.8198 79.864 18.0091 79.9175C18.3014 80.041 18.5257 80.0431 18.6821 79.9237C18.958 79.9608 19.3552 79.9299 19.8739 79.8312L20.2876 79.8867C20.6334 79.8209 20.9009 79.8147 21.0903 79.8683L21.3496 79.8189C21.3496 79.8189 21.3928 79.8106 21.4793 79.7942C21.6686 79.8477 21.8333 79.7715 21.9733 79.5657L22.1029 79.541C22.4652 79.5616 22.9057 79.5225 23.4243 79.4238L23.6837 79.3744L23.3996 79.2941L23.3749 79.1644L23.5046 79.1397L24.153 79.0163L24.4123 78.9669C24.5523 78.7611 24.7519 78.6334 25.0113 78.5841C25.3571 78.5182 25.5732 78.4771 25.6596 78.4606L26.5673 78.2877L26.697 78.263L26.5673 78.2877C26.4644 78.2177 26.3697 78.191 26.2833 78.2075C26.2133 78.3104 26.1268 78.3268 26.0239 78.2568C25.2459 78.405 24.6326 78.477 24.1839 78.4729L22.2944 78.4296L20.2753 78.411C20.2753 78.411 20.2238 78.376 20.1209 78.306C20.018 78.236 20.0015 78.1496 20.0715 78.0467L19.8122 78.0961L19.4232 78.1701L19.2935 78.1948C19.38 78.1784 19.4149 78.1269 19.3985 78.0405C19.382 77.954 19.3738 77.9108 19.3738 77.9108C19.3573 77.8244 19.4438 77.8079 19.6331 77.8614L20.0221 77.7873L20.2815 77.738L20.5408 77.6886L22.5599 77.7072C22.8193 77.6578 22.9407 77.5899 22.9243 77.5034C22.9942 77.4005 23.1157 77.3326 23.2886 77.2997C24.2395 77.1186 24.9393 77.0301 25.388 77.0342C25.5609 77.0013 25.6123 77.0363 25.5423 77.1392L25.6967 77.2442L26.7588 77.1763C27.0181 77.1269 27.1745 77.0075 27.228 76.8182C27.298 76.7153 27.3845 76.6988 27.4874 76.7688C27.6603 76.7359 27.7982 76.7544 27.9011 76.8244C28.2469 76.7585 28.4548 76.6741 28.5247 76.5712C28.6112 76.5548 28.6544 76.5465 28.6544 76.5465C28.638 76.4601 28.6297 76.4169 28.6297 76.4169L28.7594 76.3922C28.6894 76.4951 28.7059 76.5815 28.8088 76.6515C28.8952 76.6351 28.9384 76.6268 28.9384 76.6268L29.5621 76.3737L29.6918 76.349C29.7453 76.1596 29.8585 76.0485 30.0314 76.0156C30.2043 75.9826 30.334 75.958 30.4204 75.9415C30.8526 75.8592 31.3116 75.6822 31.7974 75.4105L32.81 75.0833C32.9829 75.0504 33.2258 74.9145 33.5387 74.6758L34.1623 74.4226C34.6316 74.0645 34.9095 73.8772 34.9959 73.8608C35.2553 73.8114 35.4981 73.6756 35.7246 73.4533C36.0374 73.2145 36.2803 73.0787 36.4532 73.0458L36.5829 73.0211L36.6076 73.1508L36.5026 73.3051L36.6322 73.2804L36.8669 73.1014C36.9204 72.912 37.1036 72.698 37.4165 72.4592C37.4 72.3728 37.435 72.3213 37.5214 72.3049L37.2621 72.3542L37.1324 72.3789L36.8978 72.558L36.9781 72.274L37.0584 71.9899L36.799 72.0393C36.729 72.1422 36.5211 72.2266 36.1754 72.2925C36.1589 72.206 36.1074 72.171 36.021 72.1875L36.2803 72.1381C36.5397 72.0887 36.7043 72.0126 36.7743 71.9096C36.9307 71.7903 37.0872 71.6709 37.2436 71.5515C37.3301 71.5351 37.3568 71.4404 37.3239 71.2675L37.1942 71.2922C36.5356 71.5968 36.1445 71.8952 36.021 72.1875C36.0045 72.101 35.9531 72.066 35.8666 72.0825C35.8337 71.9096 35.7823 71.8746 35.7123 71.9775L34.36 72.6382L34.255 72.7925L34.4094 72.8975C34.4794 72.7946 34.6008 72.7267 34.7737 72.6938L35.033 72.6444L34.9527 72.9284L33.2115 73.6631L31.5998 74.3732C31.1141 74.6448 30.7415 74.8054 30.4822 74.8547C30.4987 74.9412 30.4637 74.9926 30.3772 75.0091C30.3608 74.9227 30.3525 74.8794 30.3525 74.8794L29.8338 74.9782C29.7803 75.1676 29.6671 75.2787 29.4942 75.3116C29.3213 75.3446 29.1917 75.3693 29.1052 75.3857C28.7594 75.4516 28.5165 75.5874 28.3766 75.7932C28.3766 75.7932 28.3334 75.8015 28.2469 75.8179C28.1605 75.8344 28.0823 75.8941 28.0123 75.997L27.1046 76.1698L25.8079 76.4168C24.9434 76.5814 24.3301 76.6534 23.9678 76.6328C23.5356 76.7151 22.8708 76.7522 21.9734 76.7439L20.0839 76.7006L19.7999 76.6203C19.7834 76.5339 19.6888 76.5071 19.5159 76.54L19.2565 76.5894L19.2318 76.4597L19.3368 76.3054C20.0613 76.3466 20.9587 76.3548 22.029 76.3302C22.2183 76.3837 22.5291 76.3693 22.9614 76.287L23.4553 76.0586L23.8443 75.9845L25.246 75.5832C25.3325 75.5667 25.3839 75.6017 25.4004 75.6881C25.5198 75.8446 25.6227 75.9146 25.7091 75.8981C25.882 75.8652 26.0117 75.8405 26.0981 75.824L26.5921 75.5956C26.6785 75.5791 26.7135 75.5276 26.6971 75.4412L26.5674 75.4659L26.413 75.3609L26.6724 75.3115L26.8021 75.2868C27.1808 75.3939 27.4133 75.4392 27.4998 75.4227C27.7591 75.3733 28.1317 75.2128 28.6174 74.9411C29.0497 74.8588 29.3872 74.7497 29.6301 74.6139C29.9594 74.4616 30.2455 74.3175 30.4884 74.1817L30.6428 74.2867L30.5131 74.3114L30.0438 74.6695L30.5625 74.5707C31.0482 74.299 31.3343 74.155 31.4208 74.1385L31.3961 74.0088L31.0318 74.2126C30.9453 74.2291 30.8939 74.1941 30.8774 74.1076C31.2067 73.9553 31.4928 73.8113 31.7357 73.6754C31.9786 73.5396 32.2214 73.4038 32.4643 73.2679L33.8166 72.6073C33.973 72.4879 34.1809 72.4035 34.4403 72.3541C34.6132 72.3212 34.6481 72.2698 34.5452 72.1998L34.6502 72.0454L34.9096 71.996C35.0824 71.9631 35.2471 71.8869 35.4035 71.7676C35.5435 71.5618 35.7349 71.3909 35.9778 71.2551C35.9778 71.2551 36.0478 71.1522 36.1878 70.9464L36.1631 70.8167L36.1878 70.9464C36.2042 71.0328 36.2207 71.1193 36.2371 71.2057C36.3236 71.1892 36.4018 71.1296 36.4718 71.0266L36.9411 70.6685C36.7888 70.3392 36.7991 70.1581 36.972 70.1252C37.2313 70.0758 37.4042 70.0428 37.4907 70.0264C37.75 69.977 37.8714 69.9091 37.855 69.8226C37.9249 69.7197 37.9517 69.625 37.9352 69.5386C37.9188 69.4522 37.9106 69.4089 37.9106 69.4089C37.7212 69.3554 37.713 69.3122 37.8859 69.2793L38.7195 68.7174L38.8491 68.6927L38.8738 68.8224L38.7935 69.1064L38.8429 69.3657L39.1023 69.3164L39.8062 68.7792L39.9112 68.6248L39.7815 68.6495L39.6518 68.6742L39.6272 68.5445L40.0964 68.1864L40.5904 67.958L40.6954 67.8036L40.9547 67.7542C41.3005 67.6884 41.5619 67.4146 41.739 66.933C41.7225 66.8466 41.7575 66.7951 41.8439 66.7787C42.3297 66.507 42.6858 66.26 42.9122 66.0377L43.1468 65.8587L43.2271 65.5746L42.9925 65.7537L42.4985 65.9821L42.8134 65.5191L43.2827 65.1609L43.542 65.1115L43.4927 64.8522L43.363 64.8769L42.659 65.4141C42.4326 65.6364 42.198 65.8154 41.9551 65.9512C41.7122 66.0871 41.5126 66.2147 41.3561 66.3341C41.1833 66.367 41.0268 66.4864 40.8869 66.6922L40.6028 66.6119C40.6893 66.5954 40.7243 66.544 40.7078 66.4575L41.6464 65.7413L41.7514 65.5869L41.492 65.6363L41.2574 65.8154C40.9445 66.0541 40.5967 66.3443 40.2138 66.686C39.8145 66.9412 39.3288 67.2128 38.7566 67.501L37.429 68.2913L35.6074 69.3101L34.7738 69.8719L34.6441 69.8966L32.5632 70.9648C32.1639 71.22 31.6781 71.4916 31.1059 71.7798C30.6037 71.965 30.188 72.1337 29.8586 72.286C29.7022 72.4054 29.4511 72.498 29.1053 72.5639L28.9756 72.5886L27.5987 73.1195C27.1129 73.3912 26.6539 73.5682 26.2217 73.6505C25.8224 73.9057 25.1905 74.1156 24.326 74.2803L23.0293 74.5272L22.8997 74.5519C22.9161 74.6383 22.9676 74.6733 23.054 74.6569L23.9061 74.8977C23.9926 74.8813 24.044 74.9163 24.0605 75.0027L23.9308 75.0274C23.4821 75.0233 22.912 75.087 22.2204 75.2187L20.4853 75.2804L19.9173 75.1199C19.7444 75.1528 19.6065 75.1343 19.5036 75.0643C18.7626 74.9366 18.2974 74.8461 18.1081 74.7925L16.6076 74.6752C16.5047 74.6052 16.4018 74.5352 16.2989 74.4652C16.1096 74.4117 15.877 74.3664 15.6012 74.3293L15.0331 74.1688C14.465 74.0082 13.9752 73.788 13.5636 73.508C13.4771 73.5245 13.4771 73.5245 13.5636 73.508C13.5471 73.4216 13.5389 73.3784 13.5389 73.3784C13.6088 73.2755 13.7817 73.2425 14.0575 73.2796C15.7082 73.9506 17.6388 74.21 19.8494 74.0578C20.9197 74.0332 21.7141 73.9714 22.2328 73.8727L24.0235 73.3973L25.0609 73.1997L26.5675 72.6441L27.2961 72.2366L27.4258 72.2119C27.6522 71.9896 27.9815 71.8373 28.4138 71.755C28.916 71.5697 29.2885 71.4092 29.5314 71.2734C29.515 71.1869 29.5499 71.1355 29.6364 71.119C29.6199 71.0326 29.6549 70.9811 29.7414 70.9647L29.482 71.014C29.4656 70.9276 29.4141 70.8926 29.3277 70.9091L29.4573 70.8844C30.2889 70.5469 30.9208 70.3369 31.353 70.2546C32.0446 70.1229 32.5735 69.843 32.9399 69.4149L33.0696 69.3902L33.3289 69.3408C33.5018 69.3079 33.8311 69.1556 34.3169 68.8839L34.5515 68.7049C35.0373 68.4332 35.3934 68.1862 35.6198 67.964C35.6198 67.964 35.9594 67.6305 36.6387 66.9637L36.9783 66.6303C37.2212 66.4944 37.6987 66.1796 38.4108 65.6856C39.5223 64.9365 40.3045 64.3396 40.7573 63.895C41.0866 63.7427 41.3563 63.5122 41.5662 63.2035C42.5048 62.4873 43.1573 61.9151 43.5236 61.487C43.9065 61.1453 44.2543 60.8551 44.5672 60.6164C44.8636 60.2912 45.125 60.0175 45.3514 59.7952C46.4506 58.5109 46.9651 57.9202 46.8952 58.0231C47.488 57.3727 47.8811 56.85 48.0746 56.4548L48.8897 55.0902L49.9457 52.8735C49.9992 52.6842 50.0959 52.4866 50.2359 52.2808C50.3759 52.0749 50.4994 51.7827 50.6064 51.404L50.5323 51.015L50.5076 50.8853C50.4912 50.7988 50.4747 50.7124 50.4582 50.626C50.5118 50.4366 50.4871 50.3069 50.3842 50.2369L50.0075 48.9649L49.8779 48.9896C49.6885 48.9361 49.5774 48.8229 49.5445 48.65C49.598 48.4607 49.6165 48.3228 49.6 48.2363C49.6536 48.047 49.6556 47.8226 49.6062 47.5633C49.5733 47.3904 49.5054 47.2689 49.4025 47.199C49.2996 47.129 49.1967 47.059 49.0938 46.989L48.4763 46.5691L48.1923 46.4888C47.122 46.5135 46.3275 46.5752 45.8088 46.674L44.3825 46.9456C44.296 46.9621 44.261 47.0135 44.2775 47.1C44.294 47.1864 44.259 47.2379 44.1725 47.2543C44.0861 47.2708 44.0428 47.279 44.0428 47.279C43.5942 47.2749 43.1269 47.4087 42.6412 47.6803C42.5012 47.8862 42.4148 47.9026 42.3818 47.7297L41.8138 47.5692L40.9061 47.742L40.7764 47.7667C40.657 47.6103 40.4595 47.5135 40.1837 47.4765C39.8914 47.353 39.6938 47.2562 39.5909 47.1862L39.1772 47.1307L38.3992 47.2788L37.8311 47.1183L37.7014 47.143C37.6685 46.9701 37.5141 46.8651 37.2383 46.828C37.049 46.7745 36.8946 46.6695 36.7753 46.5131L36.4171 46.0438C36.3678 45.7845 36.2731 45.7577 36.1331 45.9635C35.9067 46.1858 35.6659 46.0973 35.4107 45.698L34.9538 44.71L34.7994 44.605C34.4536 44.6709 34.3857 44.5495 34.5957 44.2407C34.5792 44.1543 34.5195 44.0761 34.4166 44.0061C34.3837 43.8332 34.4104 43.7385 34.4969 43.7221C34.5669 43.6191 34.6533 43.6027 34.7562 43.6727C34.9291 43.6397 35.0588 43.615 35.1452 43.5986L35.5589 43.6542L35.9233 43.4504L35.8986 43.3208L35.7689 43.3454L35.6392 43.3701L35.7195 43.0861C35.7195 43.0861 35.7627 43.0779 35.8492 43.0614C35.9192 42.9585 36.0056 42.942 36.1085 43.012C36.2279 43.1685 36.3493 43.1005 36.4728 42.8083C36.5428 42.7054 36.5778 42.6539 36.5778 42.6539C36.6643 42.6374 36.7157 42.6724 36.7322 42.7589C36.8515 42.9153 37.0409 42.9688 37.3002 42.9194L37.7942 42.691C38.0536 42.6416 38.0803 42.5469 37.8745 42.407L37.8498 42.2773L38.455 41.2214C38.525 41.1185 38.527 40.8942 38.4612 40.5484C38.2389 40.322 38.0578 40.3117 37.9178 40.5175C37.8478 40.6204 37.7614 40.6369 37.6585 40.5669C37.642 40.4805 37.5905 40.4455 37.5041 40.4619L37.4547 40.2026C37.4218 40.0297 37.4053 39.9432 37.4053 39.9432C37.3724 39.7704 37.2859 39.7868 37.146 39.9926L37.0163 40.0173C36.8434 40.0503 36.617 40.2725 36.3371 40.6842C36.2712 40.3384 36.1251 40.2766 35.8987 40.4989C35.7258 40.5318 35.6229 40.4619 35.5899 40.289C35.5735 40.2025 35.4623 40.0893 35.2565 39.9493C35.1371 39.7929 35.026 39.6797 34.9231 39.6097C34.8202 39.5397 34.6123 39.6241 34.2994 39.8629L33.7252 40.3753C33.6387 40.3918 33.579 40.3136 33.5461 40.1407C33.5132 39.9678 33.5503 39.692 33.6573 39.3133C33.6244 39.1404 33.6264 38.916 33.6635 38.6402C33.6841 38.278 33.6347 38.0187 33.5153 37.8622C33.4495 37.5164 33.5648 37.181 33.8612 36.8558L33.8365 36.7261C33.6306 36.5861 33.6327 36.3618 33.8427 36.0531L34.4478 34.9972C34.6907 34.8614 34.9253 34.6823 35.1518 34.46C35.4482 34.1348 35.726 33.9475 35.9854 33.8982L36.325 33.5647L37.5106 31.3234L39.1408 28.5942L40.6167 25.7601L43.0373 21.5367C43.8277 20.0424 44.2579 19.2438 44.3279 19.1409L44.4082 18.8569L44.0192 18.931L41.4134 20.7709L40.1352 21.8206L38.4927 23.074C37.6776 23.498 37.0437 23.9322 36.5908 24.3768C36.348 24.5126 36.1051 24.6485 35.8622 24.7843C35.7058 24.9037 35.5493 25.023 35.3929 25.1424C34.6478 25.4635 34.1703 25.7784 33.9603 26.0871C33.6475 26.3258 33.3696 26.5131 33.1267 26.649C32.8674 26.6983 32.6513 26.7395 32.4784 26.7724C32.3055 26.8054 32.0626 26.9412 31.7498 27.1799L31.3361 27.1243L31.157 26.8897C30.9347 26.6633 30.7536 26.653 30.6136 26.8588C30.6301 26.9452 30.5519 27.0049 30.379 27.0379C30.2761 26.9679 30.2164 26.8897 30.1999 26.8032C29.9941 26.6632 29.7615 26.618 29.5022 26.6673C29.4157 26.6838 29.2696 26.6221 29.0638 26.4821C28.825 26.1692 28.5678 25.9943 28.292 25.9572L27.9339 25.4879C27.8515 25.0557 27.6478 24.6914 27.3226 24.395C26.911 24.115 26.2606 23.5222 25.3715 22.6166L24.1921 21.3631C23.4759 20.4245 23.1034 19.6444 23.0746 19.0228C23.0088 18.677 23.0026 18.4095 23.0561 18.2201C23.2743 17.014 23.6881 16.129 24.2973 15.565C24.3673 15.4621 24.6184 15.3695 25.0507 15.2872C25.31 15.2378 25.4664 15.1185 25.5199 14.9291C25.7999 14.5175 26.1374 14.4084 26.5326 14.6019C27.0142 14.7789 27.5411 14.7233 28.1133 14.4352C28.2862 14.4023 28.4776 14.2315 28.6876 13.9227C28.7576 13.8198 28.7843 13.7251 28.7679 13.6387C28.8379 13.5358 28.9758 13.5543 29.1816 13.6943L29.4656 13.7746C29.7785 13.5358 29.9781 13.4082 30.0646 13.3918C30.151 13.3753 30.1942 13.3671 30.1942 13.3671C30.1778 13.2806 30.1696 13.2374 30.1696 13.2374C30.2231 13.048 30.2581 12.9966 30.2745 13.083C30.291 13.1695 30.3424 13.2045 30.4289 13.188L30.6882 13.1386C30.7582 13.0357 30.8714 12.9246 31.0279 12.8052C31.1678 12.5994 31.2131 12.3668 31.1637 12.1075C31.1308 11.9346 31.1576 11.8399 31.244 11.8234L31.3984 11.9284C31.6042 12.0684 31.8964 12.1919 32.2752 12.2989L32.6395 12.0952L32.7691 12.0705C33.012 11.9346 33.2302 11.6691 33.4237 11.274C33.5101 11.2575 33.5451 11.206 33.5287 11.1196C33.5287 11.1196 33.5637 11.0681 33.6336 10.9652C33.7736 10.7594 33.9897 10.7183 34.282 10.8418L35.1341 11.0826L35.5231 11.0085C36.1817 10.7039 36.6675 10.4323 36.9804 10.1935C38.2977 9.58434 39.2774 9.08422 39.9196 8.69318L41.9758 7.49536C42.1322 7.37599 42.2887 7.25662 42.4451 7.13725C42.688 7.00141 42.8876 6.87381 43.044 6.75444L43.5133 6.39633C43.8262 6.15758 44.1123 6.01351 44.3716 5.96412L45.8042 5.01945C46.29 4.74778 46.6893 4.49258 47.0021 4.25383C47.4879 3.98216 48.1115 3.72902 48.8731 3.49441C49.6182 3.17335 50.2336 2.87699 50.7193 2.60533L54.097 1.29024C54.4427 1.22439 54.7185 1.26145 54.9244 1.40141L55.1837 1.35202C55.3401 1.23265 55.5912 1.14004 55.937 1.07419C56.0235 1.05773 56.1017 0.998043 56.1717 0.895135C56.2581 0.878672 56.2931 0.827216 56.2766 0.740765L56.326 1.00011L55.8937 2.96365C55.8237 3.06656 55.797 3.16123 55.8135 3.24768C55.8999 3.23121 55.9514 3.26621 55.9678 3.35266L56.4556 3.79725L56.7643 4.0072L56.8446 3.72317L56.7952 3.46383L56.9249 3.43914C57.0113 3.42267 57.0628 3.45767 57.0793 3.54411C57.2768 4.58147 57.8119 5.50975 58.6846 6.32896C59.5572 7.14817 60.1541 7.93032 60.4752 8.67541L61.1358 10.0277L61.2902 10.1327C61.496 10.2726 61.7183 10.4991 61.957 10.8119L62.1361 11.0466L62.2904 11.1515C62.3233 11.3244 62.3213 11.5488 62.2842 11.8246C62.3336 12.0839 62.2883 12.3165 62.1484 12.5223C62.0413 12.901 62.0043 13.1768 62.0372 13.3497C62.0701 13.5226 62.0516 13.6605 61.9816 13.7634C62.0145 13.9363 61.9445 14.0392 61.7716 14.0721L61.6111 14.6402C61.0183 15.2906 60.5819 15.8216 60.302 16.2332L56.6216 22.309L54.7815 25.3469L51.9162 30.0581L50.7059 32.1698L50.1007 33.2256C49.8537 33.8102 49.7117 34.2403 49.6746 34.5161C49.6376 34.7919 49.7055 34.9134 49.8784 34.8804L52.4841 35.8623C52.5705 35.8459 52.622 35.8809 52.6384 35.9673C52.8443 36.1073 53.1365 36.2308 53.5152 36.3378C54.0668 36.4119 54.4188 36.6137 54.5711 36.943L54.8551 37.0233C54.9416 37.0068 54.993 37.0418 55.0095 37.1282L54.9045 37.2826C54.6452 37.332 54.6184 37.4267 54.8242 37.5666C55.2688 38.0195 55.559 38.3673 55.6948 38.6102C55.8307 38.8531 56.0015 39.0445 56.2073 39.1844C56.4831 39.2215 56.6725 39.275 56.7754 39.345L57.3434 39.5056L59.0661 40.79C59.3749 40.9999 59.5292 41.1049 59.5292 41.1049C59.6445 41.71 59.77 42.134 59.9058 42.3769L59.9799 42.7659L60.8011 43.5501L60.8258 43.6798C60.6858 43.8856 60.6838 44.11 60.8196 44.3528C61.0254 44.4928 61.1366 44.606 61.153 44.6925L61.258 44.5381L61.2086 44.2788L61.363 44.3837L61.9311 44.5443L61.9804 44.8036L61.9002 45.0877C61.9331 45.2606 61.9928 45.3388 62.0792 45.3223L62.3386 45.2729L62.6535 44.8098L62.9128 44.7605C62.9293 44.8469 62.8943 44.8984 62.8078 44.9148C62.425 45.2565 62.1965 45.7031 62.1224 46.2547L62.1965 46.6437C62.1965 46.6437 62.2047 46.6869 62.2212 46.7734C62.2212 46.7734 62.1697 46.7384 62.0668 46.6684L61.9372 46.6931L61.0109 48.8851L60.9306 49.1691C61.0335 49.2391 61.05 49.3255 60.98 49.4285C60.98 49.4285 60.9367 49.4367 60.8503 49.4531C60.7803 49.5561 60.7536 49.6507 60.77 49.7372C60.7865 49.8236 60.8379 49.8586 60.9244 49.8422L61.5171 50.1324C61.723 50.2724 61.8444 50.2044 61.8815 49.9286C61.9679 49.9122 62.0111 49.9039 62.0111 49.9039C62.0811 49.801 62.0214 49.7228 61.8321 49.6693C61.8321 49.6693 61.7888 49.6775 61.7024 49.694C61.7024 49.694 61.6942 49.6508 61.6777 49.5643L61.863 49.1259C61.8465 49.0395 61.8815 48.988 61.9679 48.9716C62.0544 48.9551 62.1326 48.8954 62.2026 48.7925C62.2561 48.6031 62.2746 48.4652 62.2582 48.3788L62.2891 47.8354L62.6843 47.0883L62.8139 47.0636L62.8386 47.1933C62.7851 47.3826 62.783 47.607 62.8324 47.8663C62.8654 48.0392 62.8901 48.1689 62.9065 48.2553C62.923 48.3418 62.9045 48.4797 62.8509 48.669C62.7809 48.7719 62.711 48.8749 62.641 48.9778C62.501 49.1836 62.5257 49.3132 62.7151 49.3668C62.818 49.4368 62.9394 49.3688 63.0794 49.163L63.2893 48.8543C63.2729 48.7678 63.3079 48.7164 63.3943 48.6999L63.4437 48.9593L63.2584 49.3977C63.1185 49.6035 63.2214 49.6735 63.5672 49.6076L63.6968 49.5829L63.8265 49.5582L63.8512 49.6879L63.6166 49.867L63.6906 50.256L63.9747 50.3362L64.1043 50.3115L63.9994 50.4659L63.3695 51.3921L63.2892 51.6761L63.493 52.0404C63.353 52.2463 63.4127 52.3245 63.672 52.2751L63.6967 52.4048L63.4312 53.1272L63.3509 53.4112C63.4538 53.4812 63.4703 53.5677 63.4003 53.6706C63.4168 53.757 63.425 53.8002 63.425 53.8002C62.8445 54.9858 62.5193 55.63 62.4493 55.7329L61.344 57.6902C61.0105 58.2912 60.6256 58.8572 60.1892 59.3882L57.9601 62.5002L56.7806 64.0685L54.8726 66.0443L53.2239 67.9708L50.6119 70.4838L47.6109 73.0709L43.8072 75.6765L40.2134 77.9733L38.0275 79.1958C36.8831 79.7721 36.0166 80.1611 35.4279 80.3628L32.464 81.7334L29.6854 82.6657L29.6607 82.536L29.636 82.4064L29.5063 82.4311C29.1235 82.7727 28.578 82.9662 27.87 83.0114C27.2649 83.1267 26.8326 83.209 26.5733 83.2584ZM20.2444 78.9544C20.2279 78.8679 20.1765 78.8329 20.09 78.8494L20.2197 78.8247L20.4543 78.6456L22.2141 78.7136C22.2141 78.7136 22.2224 78.7568 22.2388 78.8433C22.2388 78.8433 22.282 78.8351 22.3685 78.8186L22.2388 78.8433L21.8498 78.9174L20.2444 78.9544ZM24.2703 77.5158L24.2456 77.3861C24.0563 77.3326 23.7455 77.347 23.3133 77.4293L23.1836 77.454L23.338 77.559L23.8813 77.5899L24.2703 77.5158ZM26.8575 77.695C27.5491 77.5633 28.0163 77.4295 28.2592 77.2937L28.4939 77.1146L28.2345 77.164L27.9752 77.2134L25.1224 77.7567L24.8878 77.9357C25.0607 77.9028 25.1554 77.9295 25.1718 78.016C25.2747 78.086 25.4559 78.0963 25.7152 78.0469C25.8881 78.014 26.0528 77.9378 26.2092 77.8184C26.4521 77.6826 26.6682 77.6415 26.8575 77.695ZM31.8405 79.1647L32.0751 78.9857C31.9722 78.9157 31.8343 78.8972 31.6614 78.9301C31.6779 79.0165 31.6429 79.068 31.5564 79.0845L31.5811 79.2141L31.7108 79.1894L31.8405 79.1647ZM33.1434 78.2448L33.273 78.2201C33.1866 78.2365 33.1351 78.2015 33.1187 78.1151L32.1307 78.572C32.1472 78.6584 32.1986 78.6934 32.2851 78.6769L33.1434 78.2448ZM33.7732 77.3186L33.9029 77.2939L33.7732 77.3186L31.6676 78.257C31.5812 78.2735 31.5379 78.2817 31.5379 78.2817C31.5544 78.3682 31.5626 78.4114 31.5626 78.4114L31.717 78.5164L33.7732 77.3186ZM31.9146 76.7319C32.0875 76.699 32.1658 76.6393 32.1493 76.5528L32.279 76.5282L32.1493 76.5528L32.0196 76.5775L31.89 76.6022L31.6553 76.7813L31.9146 76.7319ZM32.8038 75.7563L32.6495 75.6514L32.3099 75.9848L32.5939 76.0651L32.8038 75.7563ZM35.3539 77.1519C35.1481 77.0119 35.0452 76.942 35.0452 76.942C34.9588 76.9584 34.8456 77.0696 34.7056 77.2754L34.8847 77.51L35.3539 77.1519ZM28.142 73.1504L28.2717 73.1257L30.5317 72.2922L30.6614 72.2676C30.6614 72.2676 30.6696 72.3108 30.686 72.3972C30.686 72.3972 30.6428 72.4055 30.5564 72.4219C30.4864 72.5248 30.365 72.5927 30.1921 72.6257C29.6734 72.7244 29.0847 72.9261 28.4261 73.2307L28.142 73.1504ZM34.1808 75.2254L34.4155 75.0463L34.6748 74.9969L34.6254 74.7376L34.3908 74.9166L34.2611 74.9413L33.1682 75.5526C33.1682 75.5526 33.1764 75.5958 33.1929 75.6823C33.1929 75.6823 33.1496 75.6905 33.0632 75.7069L33.3225 75.6576L34.1808 75.2254ZM31.427 73.4655L31.6616 73.2864L31.921 73.237C31.781 73.4428 31.711 73.5458 31.711 73.5458L31.427 73.4655ZM33.4214 73.3544C33.4049 73.268 33.4399 73.2165 33.5264 73.2L33.267 73.2494L33.0077 73.2988C32.5219 73.5705 32.1494 73.731 31.8901 73.7804C31.9065 73.8668 31.8715 73.9183 31.7851 73.9348L31.9148 73.9101L33.4214 73.3544ZM38.361 76.7136C38.3446 76.6272 38.2931 76.5922 38.2067 76.6086L37.8424 76.8124L37.9967 76.9174L38.361 76.7136ZM35.0451 79.7638L38.3239 77.93C38.6533 77.7777 39.0443 77.4793 39.4972 77.0347C39.6536 76.9154 39.7483 76.9421 39.7812 77.115C39.7977 77.2015 39.8923 77.2282 40.0652 77.1953C40.3781 76.9566 40.656 76.7693 40.8988 76.6334C41.2282 76.4811 41.5143 76.3371 41.7571 76.2012L42.9304 75.306C42.9304 75.306 43.0004 75.203 43.1403 74.9972C43.2268 74.9808 43.3132 74.9643 43.3997 74.9478C43.5026 75.0178 43.6322 74.9931 43.7887 74.8738L43.764 74.7441C43.7475 74.6576 43.6961 74.6227 43.6096 74.6391L43.1403 74.9972C43.0539 75.0137 43.0024 74.9787 42.986 74.8923L42.8563 74.9169L41.893 75.5035L41.788 75.6579L41.7078 75.9419L41.1088 76.3247L40.8495 76.3741C40.9359 76.3576 40.9709 76.3062 40.9544 76.2197C41.0409 76.2033 41.0759 76.1518 41.0594 76.0654L40.7754 75.9851L39.2131 76.9545L34.8661 79.5292L34.7858 79.8132L35.0451 79.7638ZM31.9087 71.7613C31.8387 71.8642 31.8037 71.9156 31.8037 71.9156C31.7872 71.8292 31.779 71.786 31.779 71.786L31.7543 71.6563C32.0136 71.6069 32.2215 71.5225 32.3779 71.4032C32.4644 71.3867 32.5159 71.4217 32.5323 71.5081L32.4026 71.5328C32.3327 71.6357 32.168 71.7119 31.9087 71.7613ZM33.0139 72.6258C33.1003 72.6093 33.1436 72.6011 33.1436 72.6011C33.1271 72.5146 33.1189 72.4714 33.1189 72.4714C33.4317 72.2327 33.6314 72.1051 33.7178 72.0886C33.7014 72.0022 33.7014 72.0022 33.7178 72.0886C33.8043 72.0721 33.8475 72.0639 33.8475 72.0639L33.7672 72.3479L33.1683 72.7307L33.0139 72.6258ZM39.2749 75.8677L39.2502 75.738L39.1206 75.7627L38.5463 76.2752L38.571 76.4049L39.2749 75.8677ZM33.156 71.255C33.0695 71.2715 33.0263 71.2797 33.0263 71.2797C33.0098 71.1932 33.0016 71.15 33.0016 71.15L33.7302 70.7425L34.0143 70.8228L33.7549 70.8722C33.6849 70.9751 33.5635 71.043 33.3906 71.0759C33.3042 71.0924 33.226 71.1521 33.156 71.255ZM34.1871 71.7305C34.3436 71.6111 34.5 71.4917 34.6564 71.3724C34.8128 71.253 35.0207 71.1686 35.2801 71.1192C35.3501 71.0163 35.5312 71.0266 35.8234 71.1501L35.5888 71.3292C35.5188 71.4321 35.3109 71.5165 34.9651 71.5823L34.4959 71.9404L34.1068 72.0145L34.1871 71.7305ZM38.4969 76.0159C38.6698 75.983 38.8262 75.8636 38.9662 75.6578C39.2255 75.6084 39.4334 75.524 39.5899 75.4046C39.8327 75.2688 39.9892 75.1494 40.0591 75.0465C40.2156 74.9271 40.6149 74.6719 41.2571 74.2809L41.9363 73.6141L41.8066 73.6387C41.1645 74.0298 40.7651 74.285 40.6087 74.4044L39.6701 75.1206L39.5405 75.1453C39.4211 74.9889 39.2914 75.0136 39.1515 75.2194L38.1882 75.8059C38.1017 75.8224 38.0667 75.8738 38.0832 75.9603L38.2129 75.9356L38.3178 75.7812L38.5772 75.7318L38.4722 75.8862C38.3858 75.9027 38.3425 75.9109 38.3425 75.9109C38.359 75.9974 38.3672 76.0406 38.3672 76.0406L38.4969 76.0159ZM41.3187 76.016C41.4587 75.8102 41.5719 75.699 41.6584 75.6826L41.609 75.4232L41.2941 75.8863L41.3187 76.016ZM34.3786 70.619L34.2242 70.5141C34.3107 70.4976 34.3457 70.4461 34.3292 70.3597L34.5885 70.3103L34.7182 70.2856L34.5885 70.3103L34.6132 70.44C34.6997 70.4235 34.7511 70.4585 34.7676 70.545L34.6379 70.5697L34.3786 70.619ZM37.4842 76.3431C37.7642 75.9315 37.9041 75.7256 37.9041 75.7256C37.9041 75.7256 37.8959 75.6824 37.8795 75.596C37.9494 75.4931 38.0277 75.4334 38.1141 75.4169C38.4763 75.4375 38.7624 75.2935 38.9724 74.9847C39.3552 74.6431 39.6763 74.4476 39.9357 74.3982L40.1703 74.2191L40.1456 74.0894C40.0427 74.0195 40.0345 73.9762 40.1209 73.9598C40.1909 73.8569 40.2259 73.8054 40.2259 73.8054L41.8437 72.4223C42.2966 71.9778 42.6876 71.6793 43.017 71.527L43.1466 71.5023L43.1219 71.3727C43.0355 71.3891 42.9923 71.3974 42.9923 71.3974C43.0622 71.2945 43.1405 71.2348 43.2269 71.2183L43.3319 71.064L43.0725 71.1133L42.9429 71.138C42.56 71.4797 41.9693 71.9057 41.1707 72.4161L41.041 72.4408L40.9916 72.1815C40.9916 72.1815 40.9216 72.2844 40.7817 72.4902C40.7817 72.4902 40.7117 72.5931 40.5717 72.7989L40.4667 72.9533L40.5964 72.9286L40.7261 72.9039L39.1885 74.003L38.7995 74.077L38.25 74.7192C38.25 74.7192 38.215 74.7706 38.145 74.8735C38.075 74.9765 38.0915 75.0629 38.1944 75.1329C38.1079 75.1494 38.0297 75.209 37.9597 75.3119C37.8898 75.4149 37.8033 75.4313 37.7004 75.3613C37.6839 75.2749 37.6325 75.2399 37.546 75.2564C37.546 75.2564 37.5543 75.2996 37.5707 75.386L37.0767 75.6145L36.7371 75.9479C36.91 75.915 37.0315 75.8471 37.1014 75.7441L37.2311 75.7195C37.2476 75.8059 37.2126 75.8574 37.1261 75.8738L37.0212 76.0282C37.1076 76.0117 37.1591 76.0467 37.1755 76.1332C37.2455 76.0302 37.2805 75.9788 37.2805 75.9788C37.3834 76.0488 37.3999 76.1352 37.3299 76.2381L37.3546 76.3678L37.4842 76.3431ZM36.2186 70.403L36.194 70.2733L37.0276 69.7115C37.114 69.695 37.1655 69.73 37.1819 69.8164L37.2066 69.9461C36.9473 69.9955 36.6612 70.1396 36.3483 70.3783L36.2186 70.403ZM43.3256 74.5588L43.7702 74.071L43.7455 73.9414L43.6158 73.9661L42.5476 74.707L42.5723 74.8367L42.7019 74.812L43.3256 74.5588ZM42.2142 71.5455L42.3192 71.3912L42.1895 71.4159L41.3559 71.9777L41.251 72.1321L41.3806 72.1074L42.2142 71.5455ZM40.4236 72.0209C40.4071 71.9345 40.4421 71.883 40.5285 71.8666L41.4671 71.1503C42.0928 70.6728 42.5107 70.2797 42.7206 69.971L43.0849 69.7673C42.912 69.8002 42.7906 69.8681 42.7206 69.971C42.5477 70.0039 42.4695 70.0636 42.486 70.1501C42.0167 70.5082 41.7388 70.6955 41.6524 70.7119L40.9484 71.2491C40.9649 71.3356 40.9299 71.387 40.8435 71.4035L40.3742 71.7616L40.2692 71.9159L40.4236 72.0209ZM44.4988 73.6635L45.6473 72.6386L46.2216 72.1261C46.308 72.1096 46.3348 72.015 46.3019 71.8421C46.3183 71.9285 46.2834 71.98 46.1969 71.9964L46.0672 72.0211L45.9376 72.0458C45.9211 71.9594 45.9561 71.9079 46.0425 71.8915L46.4069 71.6877L46.5118 71.5333L46.2525 71.5827L45.5486 72.1199C45.3757 72.1528 45.2542 72.2207 45.1842 72.3237C45.2007 72.4101 45.139 72.5562 44.999 72.7621C44.929 72.865 44.8158 72.9761 44.6594 73.0955C44.5729 73.1119 44.4515 73.1799 44.2951 73.2992C44.2251 73.4021 44.2065 73.54 44.2395 73.7129L44.1098 73.7376L44.1345 73.8673L44.2642 73.8426L44.4988 73.6635ZM37.5277 68.81L37.6327 68.6556L38.7257 68.0444L39.5593 67.4825L39.8433 67.5628L39.7383 67.7171L39.1641 68.2296L39.1394 68.0999L39.0097 68.1246C38.8533 68.244 38.6536 68.3716 38.4107 68.5074C38.1514 68.5568 37.9003 68.6494 37.6574 68.7853L37.5277 68.81ZM39.0899 70.6624C39.1228 70.8353 39.2092 70.8189 39.3492 70.6131C39.6785 70.4608 40.1561 70.1459 40.7818 69.6684L42.6589 68.2359L42.7886 68.2112C42.7022 68.2277 42.6589 68.2359 42.6589 68.2359C42.6425 68.1495 42.6342 68.1062 42.6342 68.1062C41.8356 68.6167 41.2881 69.0345 40.9917 69.3596C40.9917 69.3596 40.9217 69.4626 40.7818 69.6684L40.6521 69.6931C40.4957 69.8124 40.2528 69.9483 39.9235 70.1006C39.5942 70.2529 39.3595 70.4319 39.2195 70.6377L39.0899 70.6624ZM37.4846 67.8776L38.7875 66.9576C38.7875 66.9576 38.8574 66.8547 38.9974 66.6489L38.7381 66.6983C38.5981 66.9041 38.312 67.0482 37.8798 67.1305C37.8098 67.2334 37.6883 67.3013 37.5154 67.3342L37.2808 67.5133C37.0215 67.5627 36.9083 67.6738 36.9412 67.8467C36.9576 67.9331 37.0523 67.9599 37.2252 67.927L37.4846 67.8776ZM44.8694 69.9649L44.7398 69.9896L44.1408 70.3724L44.0358 70.5268L44.3198 70.6071L44.8694 69.9649ZM44.3382 74.2316C44.5441 74.3716 44.7252 74.3819 44.8816 74.2625C45.038 74.1431 45.143 73.9888 45.1965 73.7994C45.4065 73.4907 45.5712 73.4145 45.6905 73.571L45.8202 73.5463L46.6291 72.8547L47.9073 71.8051C48.2366 71.6528 48.5413 71.3708 48.8212 70.9592C48.9076 70.9427 48.9859 70.883 49.0558 70.7801C49.1958 70.5743 49.3687 70.5414 49.5745 70.6814L49.8092 70.5023C49.7227 70.5188 49.6713 70.4838 49.6548 70.3973C49.449 70.2573 49.4757 70.1627 49.7351 70.1133L49.9697 69.9342L50.05 69.6502L49.7907 69.6996C49.7042 69.716 49.6692 69.7675 49.6857 69.8539L47.9629 71.3914C47.5636 71.6466 46.9811 72.1158 46.2154 72.7991C45.9025 73.0379 45.6164 73.182 45.3571 73.2313L44.8631 73.4598L44.3135 74.1019L44.3382 74.2316ZM45.3695 71.8853L46.0487 71.2184L46.8577 70.5269L46.9626 70.3725L46.833 70.3972L45.2151 71.7803L45.1102 71.9346L45.3695 71.8853ZM40.0101 66.3217L40.714 65.7845L40.8993 65.3461L40.3806 65.4449L39.337 66.3155C39.2506 66.3319 39.2156 66.3834 39.232 66.4698L39.3617 66.4451L39.7507 66.371L40.0101 66.3217ZM44.7583 67.9705C45.3841 67.493 45.8019 67.0999 46.0119 66.7912L46.2465 66.6121L46.2218 66.4824L45.8328 66.5565C45.7793 66.7459 45.6661 66.857 45.4932 66.8899C45.3903 66.8199 45.3038 66.8364 45.2338 66.9393C45.1474 66.9558 45.0609 66.9722 44.9745 66.9887L44.5052 67.3468L44.6843 67.5815L44.604 67.8655C44.6204 67.952 44.5855 68.0034 44.499 68.0199L44.7583 67.9705ZM45.345 66.1119C45.4315 66.0955 45.6311 65.9679 45.944 65.7291C45.9275 65.6427 45.8761 65.6077 45.7896 65.6241C45.4768 65.8629 45.2771 65.9905 45.1907 66.0069C45.2071 66.0934 45.2153 66.1366 45.2153 66.1366C45.3018 66.1201 45.345 66.1119 45.345 66.1119ZM41.4982 64.9633C41.7246 64.741 42.0025 64.5537 42.3318 64.4014C42.6447 64.1627 42.8711 63.9404 43.0111 63.7346L43.715 63.1974C43.8014 63.1809 43.9147 63.0698 44.0546 62.864C43.9682 62.8804 43.925 62.8887 43.925 62.8887C43.4392 63.1603 43.1613 63.3476 43.0913 63.4505L42.0725 64.4508C42.0025 64.5537 41.8811 64.6216 41.7082 64.6546C41.6217 64.671 41.5435 64.7307 41.4735 64.8336C41.4735 64.8336 41.4303 64.8418 41.3439 64.8583C41.3439 64.8583 41.3521 64.9015 41.3685 64.988L41.4982 64.9633ZM47.0492 66.5936L47.4938 66.1058L47.5988 65.9515L47.4691 65.9762C47.3827 65.9926 47.183 66.1202 46.8702 66.359L46.9195 66.6183L47.0492 66.5936ZM46.759 67.1864L47.1233 66.9826C47.4526 66.8303 47.7655 66.5916 48.0619 66.2664C48.3583 65.9412 48.6279 65.7107 48.8708 65.5748L48.9758 65.4205C48.8893 65.4369 48.8461 65.4452 48.8461 65.4452C48.8296 65.3587 48.8214 65.3155 48.8214 65.3155L48.2471 65.828L47.5679 66.4948L47.3332 66.6739C47.0739 66.7233 46.8043 66.9538 46.5243 67.3654L46.3947 67.3901C46.4111 67.4766 46.4194 67.5198 46.4194 67.5198C46.5058 67.5033 46.549 67.4951 46.549 67.4951L46.759 67.1864ZM45.7155 65.2351L46.1848 64.877L46.1601 64.7473L46.0305 64.772L45.6908 65.1055L45.7155 65.2351ZM46.5182 65.2166C46.5882 65.1137 46.6582 65.0108 46.7282 64.9079C46.8846 64.7885 47.0843 64.6609 47.3272 64.5251L47.1728 64.4201C47.0328 64.6259 46.8064 64.8482 46.4935 65.087C46.4236 65.1899 46.3886 65.2413 46.3886 65.2413C46.475 65.2249 46.5182 65.2166 46.5182 65.2166ZM50.4143 69.4464L51.0936 68.7796L52.557 67.2916C52.7135 67.1722 52.9316 66.9067 53.2116 66.495C53.298 66.4786 53.3412 66.4703 53.3412 66.4703C53.3248 66.3839 53.3165 66.3407 53.3165 66.3407L53.0572 66.3901L52.6126 66.8778L51.6987 67.7237C50.9495 68.4935 50.5399 68.9298 50.4699 69.0327L50.155 69.4958L50.1797 69.6255L50.4143 69.4464ZM45.8512 70.1811C45.9912 69.9752 46.1044 69.8641 46.1908 69.8476C46.2608 69.7447 46.339 69.685 46.4255 69.6686C46.4954 69.5657 46.5654 69.4628 46.6354 69.3599C46.6025 69.187 46.6807 69.1273 46.8701 69.1808C47.0429 69.1479 47.1212 69.0882 47.1047 69.0017C47.3846 68.5901 47.6028 68.3246 47.7592 68.2052L47.8889 68.1805C47.9754 68.1641 48.035 68.2423 48.068 68.4152L48.2779 68.1065L48.4879 67.7977C48.4714 67.7113 48.5064 67.6598 48.5928 67.6434C48.6793 67.6269 48.6711 67.5837 48.5682 67.5137L48.8028 67.3346C48.9057 67.4046 49.0436 67.4231 49.2165 67.3902L49.4511 67.2112C49.7105 67.1618 49.8752 67.0856 49.9451 66.9827C50.1016 66.8633 50.3197 66.5978 50.5997 66.1862L50.859 66.1368L50.6244 66.3159L49.7352 67.2914C49.7352 67.2914 49.7434 67.3347 49.7599 67.4211C49.7599 67.4211 49.7167 67.4293 49.6302 67.4458L49.8895 67.3964L51.0134 66.2418L51.5877 65.7293L51.6617 66.1183C51.7317 66.0154 51.8532 65.9475 52.026 65.9146C52.1125 65.8981 52.1393 65.8034 52.1063 65.6305L51.847 65.6799L51.5877 65.7293L51.7976 65.4206C51.9211 65.1283 52.1043 64.9143 52.3472 64.7784C52.66 64.5397 52.8864 64.3174 53.0264 64.1116C53.1664 63.9058 53.3496 63.6917 53.576 63.4694C53.7859 63.1607 53.9959 62.852 54.2058 62.5433L54.1565 62.2839C54.1729 62.3704 54.1379 62.4218 54.0515 62.4383C54.035 62.3518 54.035 62.3518 54.0515 62.4383L53.5019 63.0804L51.7482 65.1612L51.4889 65.2106C51.5753 65.1942 51.6185 65.1859 51.6185 65.1859C51.6021 65.0995 51.5939 65.0563 51.5939 65.0563C52.0138 64.4388 52.2422 63.9922 52.2793 63.7164L52.5139 63.5373L52.4337 63.8214L52.304 63.8461C52.3904 63.8296 52.4337 63.8214 52.4337 63.8214L53.0079 63.3089C53.1479 63.1031 53.1232 62.9734 52.9338 62.9199C52.8309 62.8499 52.7795 62.8149 52.7795 62.8149C52.8495 62.712 52.9277 62.6523 53.0141 62.6358L53.1191 62.4815C53.362 62.3456 53.4505 62.1048 53.3846 61.759L53.255 61.7837L52.2361 62.784L51.4766 63.7349L50.0687 64.8092L47.8766 66.7048L47.1727 67.242C47.1027 67.3449 46.9895 67.456 46.8331 67.5754C46.6766 67.6947 46.6149 67.8409 46.6478 68.0138L46.6725 68.1434C46.5325 68.3493 46.4708 68.4954 46.4872 68.5818L46.197 69.1746C46.0241 69.2075 45.9027 69.2754 45.8327 69.3784C45.7463 69.3948 45.633 69.506 45.4931 69.7118C45.5095 69.7982 45.4745 69.8497 45.3881 69.8661L45.5178 69.8414L45.9068 69.7674L45.6968 70.0761L45.5919 70.2305L45.8512 70.1811ZM49.4698 65.192L50.4392 63.9324C50.5257 63.916 50.5689 63.9077 50.5689 63.9077C50.5524 63.8213 50.5442 63.7781 50.5442 63.7781C50.5442 63.7781 50.501 63.7863 50.4145 63.8028C50.3981 63.7163 50.3981 63.7163 50.4145 63.8028L49.6056 64.4943L49.161 64.9821L49.2351 65.3711L49.4698 65.192ZM46.9074 62.3207C46.8744 62.1478 46.7715 62.0778 46.5986 62.1108L46.364 62.2898L46.932 62.4504L46.9074 62.3207ZM50.186 66.1306C50.1695 66.0442 50.2045 65.9927 50.291 65.9763C50.2745 65.8898 50.3527 65.8301 50.5256 65.7972L50.4762 65.5379C50.3898 65.5543 50.3465 65.5626 50.3465 65.5626C50.3301 65.4761 50.3651 65.4247 50.4515 65.4082C50.6779 65.1859 50.9311 64.8689 51.211 64.4573C51.5774 64.0292 51.9088 63.6526 52.2052 63.3274C52.2917 63.3109 52.3266 63.2595 52.3102 63.173L52.4399 63.1483C52.4563 63.2348 52.4213 63.2862 52.3349 63.3027L52.2793 63.7164L51.7297 64.3585L51.6247 64.5129L50.9455 65.1797C50.8591 65.1962 50.8241 65.2477 50.8405 65.3341C50.857 65.4206 50.8652 65.4638 50.8652 65.4638L50.7849 65.7478L50.3403 66.2356L50.2107 66.2603L50.186 66.1306ZM50.1058 63.5928L51.2049 62.3085L51.1803 62.1788L51.0506 62.2035L49.8218 63.5125C49.8382 63.599 49.8032 63.6504 49.7168 63.6669C49.8032 63.6504 49.8547 63.6854 49.8712 63.7719L50.1058 63.5928ZM54.9901 61.7221L54.8604 61.7468L54.3664 61.9752L54.2614 62.1296L54.4158 62.2345L54.9901 61.7221ZM53.607 60.1042L53.4773 60.1289L53.1624 60.592L53.1871 60.7217L53.3168 60.697L53.607 60.1042ZM54.2491 60.6538C54.2327 60.5674 54.1812 60.5324 54.0948 60.5488L53.7798 61.0119L53.9095 60.9872L54.2491 60.6538ZM36.5346 41.7215C36.5182 41.6351 36.4667 41.6001 36.3803 41.6166C36.5202 41.4107 36.5902 41.3078 36.5902 41.3078C36.6767 41.2914 36.7281 41.3264 36.7446 41.4128L36.5346 41.7215ZM35.9974 41.0176L36.0777 40.7336L36.3371 40.6842L36.3618 40.8138L36.1271 40.9929L35.9974 41.0176ZM39.0971 41.771L38.3685 42.1785L38.3932 42.3082L38.8069 42.3638L39.0971 41.771ZM36.7014 40.4804L36.936 40.3014L37.2201 40.3816L36.9854 40.5607L36.7014 40.4804ZM60.3626 46.1867C60.4326 46.0838 60.5376 45.9294 60.6775 45.7236C60.8175 45.5178 60.836 45.3799 60.7331 45.3099C60.5109 45.0835 60.41 44.7892 60.4306 44.4269C60.4306 44.4269 60.3874 44.4352 60.3009 44.4516C60.3009 44.4516 60.2927 44.4084 60.2762 44.322L60.196 44.606L60.2207 44.7357C60.0642 44.855 60.0189 45.0876 60.0848 45.4334L60.1342 45.6927C60.1506 45.7792 60.1589 45.8224 60.1589 45.8224C60.2453 45.8059 60.2885 45.7977 60.2885 45.7977L60.1589 45.8224L60.0539 45.9768C60.0868 46.1497 60.1897 46.2196 60.3626 46.1867ZM61.4309 45.4458L61.7211 44.853C61.7046 44.7666 61.6532 44.7316 61.5667 44.7481L61.2765 45.3408L61.3012 45.4705L61.4309 45.4458Z\" fill=\"#70C7D8\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3945355 elementor-widget elementor-widget-text-editor\" data-id=\"3945355\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>De wetenschappelijke literatuur is duidelijk: aangepaste lichaamsbeweging en revalidatie blijven de basis van de behandeling van artrose, ongeacht de leeftijd of het radiologische stadium.<\/p><p>We willen mensen helpen om anders te durven bewegen, met veiligheidsrichtlijnen, advies van fysiotherapeuten en concrete voorbeelden, in plaats van alle beslissingen te laten bepalen door angst of pijn.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2dd5ec9 e-con-full e-flex e-con e-child\" data-id=\"2dd5ec9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-3b4b728 e-con-full e-flex e-con e-child\" data-id=\"3b4b728\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0bc5dc3 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"0bc5dc3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"76\" height=\"100\" viewBox=\"0 0 76 100\" fill=\"none\"><path d=\"M36.4278 95.2686C36.3249 95.1986 36.1438 95.1883 35.8844 95.2377C35.6251 95.2871 35.3843 95.1985 35.162 94.9721C34.9562 94.8322 34.8018 94.7272 34.6989 94.6572C34.596 94.5872 34.5795 94.5008 34.6495 94.3979C34.8224 94.3649 34.9088 94.3485 34.9088 94.3485C35.0982 94.402 35.125 94.3073 34.9891 94.0644C34.6804 93.8545 34.5013 93.6198 34.452 93.3605C34.3161 93.1176 34.2317 92.9097 34.1988 92.7368C34.2523 92.5475 34.2709 92.4096 34.2544 92.3231C34.4108 92.2038 34.3861 92.0741 34.1803 91.9341C34.0774 91.8642 34.0609 91.7777 34.1309 91.6748C34.2174 91.6583 34.2524 91.6069 34.2359 91.5204L34.0815 91.4155L33.5382 91.3846L33.5135 91.2549C33.6699 91.1355 33.6452 91.0059 33.4394 90.8659L32.5935 89.952L31.5438 88.6738C31.5109 88.5009 31.4512 88.4227 31.3648 88.4392C31.1919 88.4721 31.0375 88.3671 30.9017 88.1242C30.7659 87.8814 30.6897 87.7167 30.6732 87.6302C30.4674 87.4903 30.4942 87.3956 30.7535 87.3462C30.84 87.3297 30.875 87.2783 30.8585 87.1918L30.8091 86.9325L30.6301 86.6979C30.5271 86.6279 30.4592 86.5064 30.4263 86.3335C30.3934 86.1607 30.3255 86.0392 30.2226 85.9692L30.3831 85.4012L30.5128 85.3765C30.5786 85.7223 30.7639 86.2245 31.0685 86.8831L31.0931 87.0128L31.2475 87.1178L31.1672 87.4018L31.3957 87.8958C31.4657 87.7929 31.476 87.6117 31.4266 87.3524L31.1796 86.0557C31.0479 85.3641 30.9924 84.8372 31.013 84.475C30.9471 84.1292 30.9513 83.6805 31.0254 83.1289L30.8772 82.3509C30.8114 82.0051 30.7826 81.3835 30.7908 80.4861C30.8114 80.1239 30.832 79.7616 30.8526 79.3994C30.8732 79.0371 30.8938 78.6749 30.9144 78.3126L30.8897 78.183L30.8156 77.794L30.76 78.2077C30.6365 78.4999 30.5563 78.784 30.5192 79.0598C30.4821 79.3356 30.4368 79.5681 30.3833 79.7575C30.4327 80.0168 30.4039 80.3359 30.2968 80.7146C30.2886 81.612 30.3174 82.2335 30.3832 82.5793C30.3297 82.7687 30.3359 83.0363 30.4017 83.382L30.5314 83.3573L30.4202 84.1848L30.2905 84.2094L30.2658 84.0798C30.13 83.8369 30.0992 83.4397 30.1733 82.8881L30.161 81.4123L30.1734 80.0662L30.2969 77.8927C30.3669 77.7898 30.3505 77.7034 30.2476 77.6334C30.1447 77.5634 30.0767 77.442 30.0438 77.2691C30.0973 77.0797 30.1159 76.9418 30.0994 76.8554C30.0665 76.6825 30.12 76.4931 30.26 76.2873C30.3835 75.995 30.3855 75.7707 30.2662 75.6143L30.2415 75.4846C30.3979 75.3652 30.4596 75.2191 30.4267 75.0462C30.4802 74.8568 30.4988 74.7189 30.4823 74.6325C30.4658 74.546 30.5008 74.4946 30.5873 74.4781C30.7273 74.2723 30.7643 73.9965 30.6985 73.6507C30.6655 73.4778 30.6697 73.0291 30.7109 72.3046L30.6862 72.175C30.4639 71.9486 30.431 71.7757 30.5874 71.6563C30.5874 71.6563 30.5792 71.6131 30.5627 71.5266C30.5462 71.4402 30.4948 71.4052 30.4083 71.4216C30.3054 71.3517 30.2293 71.187 30.1799 70.9277L31.0383 67.6736C31.1659 66.9327 31.2668 66.2864 31.3409 65.7348C31.5015 65.1667 31.6271 64.6501 31.7176 64.1849L31.9091 63.0735L32.3538 59.7639C32.749 58.0761 33.0002 57.0429 33.1072 56.6642L33.0331 56.2752L32.7738 56.3246L30.4089 57.3125C29.3509 57.8723 28.4411 58.2695 27.6796 58.5041L25.9383 59.2388L23.419 60.1217C22.9332 60.3934 22.466 60.5271 22.0173 60.523L21.8876 60.5477C21.5954 60.4242 21.2846 60.4386 20.9553 60.5909C20.6959 60.6403 20.4798 60.6814 20.3069 60.7143C19.6153 60.846 19.1049 60.988 18.7756 61.1403C18.7756 61.1403 18.7324 61.1486 18.6459 61.165C18.543 61.0951 18.4833 61.0168 18.4668 60.9304C18.3146 60.6011 18.0737 60.5126 17.7444 60.6648C17.7444 60.6648 17.7012 60.6731 17.6147 60.6895C17.6147 60.6895 17.6065 60.6463 17.5901 60.5599C17.4871 60.4899 17.2978 60.4364 17.022 60.3993C16.7462 60.3623 16.5404 60.2223 16.4045 59.9794L15.9661 59.7942L15.0585 59.967L14.9041 59.862C14.6653 59.5492 14.4513 59.366 14.2619 59.3125C13.8503 59.0325 13.6548 58.7114 13.6754 58.3492L13.6013 57.9602C13.6013 57.9602 13.5581 57.9684 13.4716 57.9849C13.4552 57.8984 13.4119 57.9067 13.342 58.0096L12.9283 57.954L12.4405 57.5094C11.8601 56.8137 11.0224 55.943 9.92746 54.8974L8.56908 53.4092C8.10806 52.87 7.8117 52.2545 7.67999 51.563C7.54829 50.8714 7.56272 50.2416 7.72329 49.6735L8.39023 47.5309C8.63724 46.9464 8.86572 46.4998 9.07567 46.191L10.4775 42.9679L13.5773 38.0776L14.4727 36.429C14.5962 36.1368 14.728 35.8877 14.8679 35.6819C15.0079 35.4761 15.1046 35.2785 15.1582 35.0891L17.6035 30.9954C18.2333 30.0692 18.857 28.8755 19.4746 27.4142L20.265 25.9199C20.4049 25.7141 20.7055 24.9402 21.1666 23.5983L21.747 22.4127C22.0846 21.363 22.237 20.7518 22.204 20.5789C22.4634 18.6482 22.6467 17.4936 22.7537 17.1149C22.7743 16.7526 22.8546 16.4686 22.9946 16.2628C23.1181 15.9705 23.2066 15.7297 23.2601 15.5403C23.4165 15.421 23.5483 15.1719 23.6553 14.7932C23.7829 14.0523 24.1678 13.4863 24.81 13.0952C25.0529 12.9594 25.4934 12.9203 26.1314 12.9779C26.3372 13.1179 26.4751 13.1364 26.5451 13.0335C27.0638 12.9348 27.5454 13.1118 27.99 13.5646C28.0929 13.6346 28.2308 13.6531 28.4037 13.6202C28.5601 13.5008 28.733 13.4679 28.9224 13.5214C29.1817 13.472 29.3546 13.4391 29.441 13.4226C29.8897 13.4268 30.2767 13.577 30.6019 13.8734C31.0135 14.1534 31.2708 14.3283 31.3737 14.3983L33.1458 15.9421C33.2487 16.012 33.3166 16.1335 33.3495 16.3064C33.5018 16.6357 33.8003 17.0268 34.2448 17.4796L34.8067 18.3132C34.8931 18.2967 34.9014 18.34 34.8314 18.4429C34.8478 18.5293 34.8643 18.6158 34.8808 18.7022C34.5308 19.2168 34.5267 19.6655 34.8684 20.0483C34.9013 20.2212 34.8828 20.3591 34.8128 20.462C34.8457 20.6349 34.7201 21.1515 34.4361 22.0118L33.6641 24.3088L33.0528 26.0377L32.1018 28.1L31.2558 30.008C30.9594 30.3332 30.486 31.14 29.8355 32.4284L28.9401 34.077C28.8701 34.1799 28.5099 34.8756 27.8595 36.164L26.0996 38.9179C26.0996 38.9179 25.5994 39.8194 24.599 41.6223L22.8391 44.3762L21.9191 45.8951C21.6926 46.1174 21.812 46.2738 22.2772 46.3644C22.623 46.2986 22.8988 46.3356 23.1046 46.4756L23.3639 46.4262L25.1546 45.9508L25.5683 46.0064C26.0541 45.7347 26.5131 45.5577 26.9453 45.4754C27.1017 45.3561 27.3014 45.2285 27.5442 45.0926C27.7871 44.9568 28.0815 44.8559 28.4272 44.7901C28.8595 44.7078 29.197 44.5987 29.4399 44.4629L29.5943 44.5678C29.6107 44.6543 29.7054 44.681 29.8783 44.6481C30.1376 44.5987 30.5966 44.4217 31.2553 44.1172C31.2553 44.1172 31.3253 44.0142 31.4652 43.8084C31.4652 43.8084 31.457 43.7652 31.4405 43.6788C31.4241 43.5923 31.4591 43.5409 31.5455 43.5244C31.7019 43.405 31.953 43.3124 32.2988 43.2466C32.3853 43.2301 32.4367 43.2651 32.4532 43.3515C32.3832 43.4544 32.4347 43.4894 32.6076 43.4565C32.7969 43.51 33.0213 43.5121 33.2806 43.4627C33.6099 43.3104 33.861 43.2178 34.0339 43.1849C34.1904 43.0655 34.3632 43.0326 34.5526 43.0861C34.7255 43.0532 34.8902 42.977 35.0466 42.8577C35.3924 42.7918 35.8081 42.623 36.2939 42.3514C36.2939 42.3514 36.3639 42.2485 36.5038 42.0426C36.5574 41.8533 36.6109 41.6639 36.6644 41.4746C36.7015 41.1988 36.7385 40.923 36.7756 40.6472L37.2326 38.8133C37.5537 37.6772 37.7513 36.8333 37.8254 36.2817C37.986 35.7136 38.1383 35.1023 38.2824 34.4478C38.513 33.7769 38.7353 33.0627 38.9494 32.3052L39.6225 29.4896L40.0301 27.3964L41.2097 23.0062L41.9137 19.6472C42.2348 18.5111 42.5663 17.1938 42.908 15.6954L43.7108 12.8551L43.7911 12.5711C43.8817 12.1059 43.9126 11.5625 43.8838 10.941C43.9414 10.3029 44.0691 9.56194 44.2667 8.71807C44.3037 8.44227 44.5363 7.54695 44.9645 6.03211C45.2115 5.44758 45.8825 4.73751 46.9775 3.90191L47.8112 3.34005L48.83 2.33978C49.04 2.03105 49.4475 1.81907 50.0526 1.70383L50.312 1.65444C50.8306 1.55567 51.4502 1.75122 52.1705 2.24111C52.3599 2.29463 52.5575 2.39137 52.7633 2.53134C52.9526 2.58486 53.142 2.63838 53.3314 2.6919C53.4343 2.76188 53.5104 2.92655 53.5598 3.18589L54.1217 4.0195L54.1464 4.14916L54.3254 4.38381C54.3254 4.38381 54.3686 4.37557 54.4551 4.35911C54.6115 4.23974 54.663 4.27473 54.6095 4.46409C54.6259 4.55054 54.6856 4.62875 54.7885 4.69874C54.8914 4.76872 54.9861 4.79548 55.0725 4.77902C55.1055 4.95191 55.2084 5.0219 55.3813 4.98897L55.6653 5.06925C56.044 5.17629 56.3527 5.38624 56.5915 5.6991C56.8138 5.92552 56.9331 6.08195 56.9496 6.16839L57.2027 6.79205C57.318 7.39717 57.1307 8.05992 56.6408 8.78028L56.2147 10.0708C55.4036 13.8085 54.856 16.1075 54.5719 16.9679L53.1516 22.2101L52.4228 25.4395C51.9576 27.2301 51.6715 28.3148 51.5644 28.6935L50.6566 31.6882C50.3355 32.8243 50.1379 33.6682 50.0638 34.2198L49.9835 34.5038L50.2428 34.4544C50.4322 34.508 50.6998 34.5018 51.0455 34.436L52.4472 34.0346L52.5769 34.01C52.5769 34.01 52.5851 34.0532 52.6016 34.1396C52.6016 34.1396 52.5584 34.1479 52.4719 34.1643L51.379 34.7756L51.3543 34.6459L51.4592 34.4915L51.3049 34.3866C51.062 34.5224 50.638 34.6479 50.0329 34.7632L50.0576 34.8928L49.6624 35.64L49.7365 36.029L49.9958 35.9796L50.1255 35.9549C50.3148 36.0084 50.5392 36.0105 50.7985 35.9611C50.8849 35.9446 51.2925 35.7326 52.0211 35.3251L52.5151 35.0967C52.4986 35.0103 52.4904 34.967 52.4904 34.967C52.5769 34.9506 52.6201 34.9423 52.6201 34.9423C52.6736 34.753 52.7436 34.6501 52.83 34.6336C53.0029 34.6007 53.1326 34.576 53.219 34.5595C53.219 34.5595 53.2273 34.6027 53.2437 34.6892C53.2437 34.6892 53.287 34.681 53.3734 34.6645L53.2437 34.6892L53.2684 34.8189C53.0955 34.8518 52.9741 34.9197 52.9041 35.0226L53.2931 34.9485L53.7871 34.7201C53.96 34.6872 54.0114 34.7222 53.9415 34.8251C53.9579 34.9115 54.0526 34.9383 54.2255 34.9053L54.3552 34.8807C54.3552 34.8807 54.3634 34.9239 54.3799 35.0103C54.3799 35.0103 54.3366 35.0186 54.2502 35.035C53.9909 35.0844 53.783 35.1688 53.6265 35.2882L53.7068 35.0041L53.6821 34.8745L53.5525 34.8991L51.7803 36.1772C51.6238 36.2966 51.1813 36.5601 50.4527 36.9676C50.3662 36.984 50.3312 37.0355 50.3477 37.1219L50.5021 37.2269L52.089 36.3872L53.8303 35.6525L54.0896 35.6031L54.1143 35.7328L51.9037 36.8256C51.5044 37.0808 51.1484 37.3278 50.8355 37.5665C50.5226 37.8053 50.2448 37.9925 50.0019 38.1284C49.9154 38.1448 49.8372 38.2045 49.7672 38.3074C49.7672 38.3074 49.8187 38.3424 49.9216 38.4124L49.9463 38.5421C49.687 38.5915 49.5223 38.6676 49.4523 38.7705C49.4523 38.7705 49.4173 38.822 49.3473 38.9249C49.3473 38.9249 49.3906 38.9167 49.477 38.9002L49.3473 38.9249C49.0016 38.9907 48.7751 39.213 48.6681 39.5917C48.6475 39.954 48.6022 40.1866 48.5322 40.2895C48.5322 40.2895 48.5405 40.3327 48.5569 40.4191C48.6434 40.4027 48.7216 40.343 48.7916 40.2401L49.1806 40.166C49.407 39.9437 49.6581 39.8511 49.9339 39.8882C50.2797 39.8223 50.539 39.7729 50.7119 39.74C51.5435 39.4025 52.0889 39.209 52.3482 39.1596C52.5047 39.0403 52.799 38.9394 53.2312 38.8571C53.4206 38.9106 53.5585 38.9292 53.6449 38.9127C53.8014 38.7933 53.9228 38.7254 54.0092 38.709C54.0957 38.6925 54.1821 38.676 54.2686 38.6596C54.425 38.5402 54.5629 38.5587 54.6823 38.7152L56.2383 38.4188L57.2263 37.9619L57.356 37.9372C57.4753 38.0937 57.605 38.069 57.745 37.8632L57.8746 37.8385L57.8993 37.9681C57.7264 38.0011 57.5268 38.1287 57.3004 38.3509C57.0575 38.4868 56.7549 38.5444 56.3927 38.5238L56.263 38.5485L55.1207 38.9004L54.886 39.0795L54.9107 39.2091L55.1454 39.0301L55.9234 38.8819L55.9481 39.0116L55.8184 39.0363C55.5056 39.275 55.2195 39.4191 54.9601 39.4685L54.7255 39.6475C54.8284 39.7175 54.9663 39.736 55.1392 39.7031L55.8678 39.2956C56.0407 39.2627 56.1786 39.2812 56.2815 39.3512C56.368 39.3347 56.4194 39.3697 56.4359 39.4562C56.4359 39.4562 56.3926 39.4644 56.3062 39.4809L55.8122 39.7093L55.5776 39.8884L55.8616 39.9687C55.9316 39.8658 56.053 39.7978 56.2259 39.7649C56.4853 39.7155 56.6499 39.6394 56.7199 39.5365L57.2633 39.5674C57.6091 39.5015 57.9034 39.4007 58.1463 39.2648C58.3891 39.129 58.6403 39.0364 58.8996 38.987L59.0293 38.9623L58.9243 39.1167C58.7514 39.1496 58.63 39.2175 58.56 39.3204L58.4303 39.3451C58.3932 39.6209 58.2718 39.6888 58.066 39.5489C57.9795 39.5653 57.9446 39.6168 57.961 39.7032L57.8313 39.7279C57.3991 39.8102 57.0616 39.9193 56.8187 40.0551C56.5758 40.191 56.3329 40.3268 56.0901 40.4626C56.0036 40.4791 55.9686 40.5306 55.9851 40.617L56.1394 40.722C56.2794 40.5162 56.4441 40.44 56.6334 40.4935C56.8063 40.4606 56.9792 40.4277 57.1521 40.3948C57.1686 40.4812 57.1336 40.5327 57.0471 40.5491L56.4729 41.0616C56.3 41.0945 56.1785 41.1624 56.1085 41.2654C56.0221 41.2818 55.9871 41.3333 56.0036 41.4197C56.1065 41.4897 56.1229 41.5762 56.053 41.6791C56.053 41.6791 56.0097 41.6873 55.9233 41.7038C55.9398 41.7902 55.9562 41.8766 55.9727 41.9631C56.0591 41.9466 56.1023 41.9384 56.1023 41.9384C56.1723 41.8355 56.3288 41.7161 56.5716 41.5803C56.8145 41.4444 56.9792 41.3683 57.0656 41.3518L57.4546 41.2778L57.5843 41.2531C57.6707 41.2366 57.749 41.1769 57.8189 41.074C57.9754 40.9546 58.105 40.9299 58.208 40.9999C58.3315 40.7077 58.4797 40.5451 58.6526 40.5121C58.8254 40.4792 58.9551 40.4545 59.0416 40.4381L59.4306 40.364L59.0663 40.5677C58.7534 40.8065 58.2676 41.0781 57.609 41.3827C57.5555 41.5721 57.399 41.6915 57.1397 41.7408L57.0594 42.0249L57.1891 42.0002C57.5184 41.8479 57.7613 41.7121 57.9177 41.5927C58.1441 41.3704 58.3356 41.1996 58.492 41.0802L60.363 40.3208C60.3465 40.2343 60.3815 40.1829 60.4679 40.1664C60.6737 40.3064 61.0195 40.2405 61.5053 39.9689L63.2466 39.2341C63.2466 39.2341 63.2898 39.2259 63.3762 39.2094C63.4627 39.193 63.4545 39.1498 63.3516 39.0798C63.4215 38.9769 63.543 38.909 63.7159 38.876C63.7159 38.876 63.7241 38.9193 63.7406 39.0057C63.827 38.9892 63.9052 38.9296 63.9752 38.8266C64.4074 38.7443 64.9529 38.5509 65.6115 38.2463L66.1302 38.1475L66.2599 38.1228L66.1549 38.2772L65.7659 38.3513C65.4366 38.5036 65.064 38.6641 64.6482 38.8328C64.3189 38.9851 63.9978 39.1807 63.685 39.4194L59.0785 42.0435L56.0838 43.9575C54.8529 44.5503 53.4739 45.3056 51.9466 46.2235C51.3744 46.5116 50.5326 47.0303 49.4211 47.7794L46.4016 49.5638C46.2452 49.6832 46.1134 49.9322 46.0064 50.3109L45.1171 54.1083L44.4995 56.5103L43.9314 59.1715C43.9108 59.5338 43.5176 60.9972 42.7518 63.5617L41.6711 68.4706C41.2429 69.9854 40.965 71.1133 40.8374 71.8543C40.0798 75.4026 39.7463 76.9442 39.8369 76.4791C39.5364 77.253 39.1864 78.7081 38.7871 80.8445L38.0459 85.42L37.8359 88.5505C37.8853 88.8099 37.8729 89.2153 37.7988 89.767C37.8276 90.3885 37.9346 90.9504 38.1198 91.4527C38.2227 91.5226 38.2474 91.6523 38.1939 91.8417C38.1404 92.031 38.1218 92.1689 38.1383 92.2554L38.2371 92.774C38.3688 93.4656 38.1732 94.0851 37.6504 94.6326C37.6669 94.7191 37.6319 94.7705 37.5454 94.787C37.5948 95.0463 37.5331 95.1924 37.3602 95.2254L36.4278 95.2686ZM35.5202 92.6196C35.5037 92.5331 35.5387 92.4817 35.6252 92.4652C35.7116 92.4488 35.7466 92.3973 35.7302 92.3109C35.6437 92.3273 35.549 92.3006 35.4461 92.2306C35.4461 92.2306 35.4029 92.2388 35.3165 92.2553C35.3165 92.2553 35.2732 92.2635 35.1868 92.28C35.2032 92.3664 35.2547 92.4014 35.3411 92.3849L35.5202 92.6196ZM31.9144 87.797C32.0008 87.7805 32.0358 87.7291 32.0193 87.6426L31.7909 87.1487C31.7044 87.1651 31.6612 87.1734 31.6612 87.1734C31.6777 87.2598 31.6859 87.303 31.6859 87.303L31.9144 87.797ZM31.7168 86.7596C31.7003 86.6732 31.7271 86.5785 31.7971 86.4756C31.97 86.4427 31.9967 86.348 31.8774 86.1916L31.828 85.9322C31.7457 85.5 31.723 85.146 31.7601 84.8702L31.6366 84.2218L31.8898 84.8455L32.0194 84.8208C31.9207 84.3021 31.8898 83.9049 31.9269 83.6291C31.8775 83.3697 31.8569 82.7914 31.8652 81.894L31.822 80.9616C31.892 80.8587 31.8837 80.8155 31.7973 80.8319C31.7644 80.659 31.6965 80.5376 31.5935 80.4676L31.4886 80.622C31.4515 80.8978 31.4144 81.1736 31.3774 81.4494C31.3239 81.6387 31.2703 81.8281 31.2168 82.0175C31.2086 82.9148 31.2538 83.6229 31.3526 84.1416C31.2991 84.3309 31.3135 84.6417 31.3958 85.0739C31.3752 85.4362 31.4307 85.9631 31.5624 86.6547C31.5789 86.7411 31.6304 86.7761 31.7168 86.7596ZM33.3113 48.563C33.9699 48.2584 34.5586 48.0567 35.0773 47.958L35.1576 47.6739L35.1329 47.5443L35.0032 47.5689L33.2619 48.3037L33.0273 48.4827L33.3113 48.563ZM47.6304 48.2548C47.8733 48.119 48.073 47.9914 48.2294 47.872C48.4723 47.7362 48.6719 47.6086 48.8283 47.4892C49.0877 47.4398 49.3738 47.2957 49.6866 47.057L49.662 46.9273L49.5323 46.952L48.18 47.6127L47.3464 48.1745L47.3711 48.3042L47.5008 48.2795L47.6304 48.2548ZM49.73 42.3457L49.8597 42.321L49.5757 42.2407C49.5757 42.2407 49.4892 42.2572 49.3163 42.2901C49.2299 42.3066 49.1702 42.2284 49.1373 42.0555L49.0076 42.0802L48.5136 42.3086L48.5383 42.4383L48.563 42.5679L49.341 42.4198L49.73 42.3457ZM50.5143 41.5245L50.3599 41.4195L49.9956 41.6233L50.2796 41.7035L50.5143 41.5245ZM50.9218 42.2531L51.9097 41.7962L52.1444 41.6172L52.1197 41.4875L51.8603 41.5369C51.5475 41.7756 51.2614 41.9197 51.002 41.9691L50.8724 41.9938L50.6377 42.1728L50.6624 42.3025L50.9218 42.2531ZM51.5084 40.3946L51.2244 40.3143L51.0947 40.339C51.1112 40.4254 51.2223 40.5386 51.4281 40.6786L51.5084 40.3946ZM52.5643 40.9997L52.7989 40.8207C53.2312 40.7383 53.4823 40.6457 53.5522 40.5428C53.6387 40.5264 53.6655 40.4317 53.6325 40.2588L53.6078 40.1291C53.4349 40.162 53.2271 40.2464 52.9842 40.3823C52.7413 40.5181 52.5334 40.6025 52.3605 40.6354C52.3605 40.6354 52.3255 40.6869 52.2556 40.7898C52.2556 40.7898 52.2041 40.7548 52.1012 40.6848C52.0147 40.7012 51.8933 40.7692 51.7369 40.8885C51.5804 41.0079 51.5105 41.1108 51.5269 41.1973L51.6813 41.3022L52.5643 40.9997ZM52.1815 40.4008C52.2679 40.3843 52.3811 40.2732 52.5211 40.0673L52.6261 39.913L52.4964 39.9377C52.3564 40.1435 52.2432 40.2546 52.1568 40.2711C52.1568 40.2711 52.1136 40.2793 52.0271 40.2958C52.0271 40.2958 52.0189 40.2526 52.0024 40.1661C51.916 40.1826 51.8727 40.1908 51.8727 40.1908C51.8563 40.1044 51.848 40.0611 51.848 40.0611L51.7184 40.0858L51.7678 40.3452L52.1815 40.4008ZM54.7193 40.3206L54.2315 39.876L54.3118 39.5919C54.4147 39.6619 54.5361 39.594 54.6761 39.3882C54.6596 39.3017 54.6946 39.2503 54.7811 39.2338L54.497 39.1536L54.5217 39.2832C54.4517 39.3861 54.3303 39.454 54.1574 39.487C53.9845 39.5199 53.8548 39.5446 53.7684 39.5611L53.614 39.4561C53.5441 39.559 53.5255 39.6969 53.5584 39.8698C53.5914 40.0427 53.6943 40.1127 53.8672 40.0797C54.0565 40.1333 54.2027 40.195 54.3056 40.265C54.4949 40.3185 54.6411 40.3803 54.744 40.4502C54.8304 40.4338 54.8819 40.4688 54.8983 40.5552L54.7193 40.3206ZM57.8005 40.2713L58.8934 39.66L59.1774 39.7403L59.0478 39.765L57.8005 40.2713L57.6708 40.296L57.8005 40.2713ZM58.239 37.6347C58.239 37.6347 58.1525 37.6512 57.9796 37.6841C57.9796 37.6841 57.9364 37.6923 57.8499 37.7088C57.8335 37.6223 57.8335 37.6223 57.8499 37.7088C57.6771 37.7417 57.4609 37.7829 57.2016 37.8323C56.9258 37.7952 56.7097 37.8364 56.5532 37.9557C56.3804 37.9887 56.3289 37.9537 56.3989 37.8508C56.4689 37.7478 56.5471 37.6882 56.6335 37.6717C56.8229 37.7252 57.039 37.6841 57.2819 37.5482C57.5083 37.3259 57.6647 37.2066 57.7512 37.1901L58.2698 37.0913L58.3748 36.937C58.3584 36.8505 58.2637 36.8238 58.0908 36.8567C58.0208 36.9596 57.8561 37.0358 57.5968 37.0851C57.4239 37.1181 57.3292 37.0913 57.3128 37.0049C57.3992 36.9884 57.4342 36.9369 57.4177 36.8505L58.4551 36.6529L58.5848 36.6282L58.6095 36.7579L58.5292 37.0419C58.6321 37.1119 58.7268 37.1387 58.8132 37.1222C58.8997 37.1058 58.9429 37.0975 58.9429 37.0975C59.0993 36.9782 59.3504 36.8856 59.6962 36.8197L59.7209 36.9494L59.4863 37.1284C58.8276 37.433 58.4118 37.6018 58.239 37.6347Z\" fill=\"#70C7D8\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c91195 elementor-widget-laptop__width-initial elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"9c91195\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">De route duidelijker en persoonlijker maken<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e966b0f elementor-widget elementor-widget-text-editor\" data-id=\"e966b0f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Tussen de \u2018standaardbehandelingen\u2019, medicijnen, injecties, medische hulpmiddelen, operaties en nieuwe benaderingen raak je al snel de weg kwijt.<\/p><p>We bieden informatie om inzicht te krijgen in de zorgketen, de balans op te maken van wat er al is geprobeerd en innovaties in kaart te brengen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fc90eac e-con-full e-flex e-con e-parent\" data-id=\"fc90eac\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-41bff3c e-con-full e-flex e-con e-child\" data-id=\"41bff3c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f6f92e0 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"f6f92e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">En dat kleine paddenstoeltje in het logo?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d1d8e12 elementor-widget elementor-widget-text-editor\" data-id=\"d1d8e12\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Als u een paddenstoel in ons logo hebt opgemerkt, is dat geen grafische gril.Si vous avez remarqu\u00e9 un champignon dans notre logo, ce n&#8217;est pas un caprice graphique.<\/p><p> <\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Het is een bewuste knipoog naar een bestaande maar nog te weinig zichtbare onderzoekspiste: sommige biomaterialen die bij artrose worden gebruikt, zijn afgeleid van\u2026 de champignon. In Belgi\u00eb hebben onze onderzoeksteams een specifiek biopolymeer ontwikkeld, CM-chitosan, dat als vloeibaar implantaat wordt gebruikt. <\/p><p> <\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Innovatie bij artrose beperkt zich niet tot behandelingen. Ze loopt ook via een multidisciplinaire begeleiding die elke pati\u00ebnt helpt om een aangepaste en duurzame lichaamsbeweging vol te houden. Dit zorgtraject wordt altijd op maat opgebouwd, en het is uw arts die het kan co\u00f6rdineren in functie van uw situatie, in samenwerking met de andere zorgverleners die u begeleiden (kinesitherapeut, reumatoloog, sportarts, en indien nodig chirurg).  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-aec1d35 e-con-full e-flex e-con e-child\" data-id=\"aec1d35\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b4af3ff elementor-absolute elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"b4af3ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Calque_2\" data-name=\"Calque 2\" viewBox=\"0 0 268.58 79.87\"><defs><style>      .cls-1 {        fill: #2d2c78;      }    <\/style><\/defs><g id=\"Calque_1-2\" data-name=\"Calque 1\"><path class=\"cls-1\" d=\"M138.42,14.99l-.28-.06-.15-.07-.31-.1c-.19-.04-.35-.12-.47-.23,0,0-.02-.04-.07-.11l-.04-.11c-.08-.04-.17-.11-.28-.22-.11-.09-.2-.19-.26-.29l-.21-.37s-.02-.06-.01-.1c-.02-.03-.02-.05-.02-.07,0-.02,0-.03-.02-.04l-.15-.52c-.05-.18-.06-.37-.04-.57.02-.21.04-.34.05-.38-.02-.03-.02-.06-.01-.1,0-.02,0-.03-.02-.04-.02,0-.03-.03-.02-.07l-.02-.07v.06s-.02.03-.02.03v.03s-.01-.03-.03-.04l.06-.28h.03c0-.17,0-.3.02-.38l.12-.69.09-.41v-.03c-.04-.1-.05-.2-.03-.3.04-.1.07-.17.08-.21.08-.29.23-.71.44-1.28.04-.1.14-.3.29-.59.08-.16.11-.28.08-.38,0-.09.03-.18.09-.27.08-.18.23-.44.43-.79l.31-.39s.04-.03.05-.06c0-.04.03-.07.05-.09l.21-.35.14-.2c.15-.17.3-.37.46-.62.03-.04.12-.17.28-.4l.42-.56s.05-.1.07-.18l.04-.06c.18-.11.3-.24.38-.38.07-.1.15-.17.24-.21l.09-.11.71-.57c.14-.12.36-.26.68-.41l.75-.46.44-.2c.21-.06.41-.11.59-.14.28-.07.48-.11.62-.13l.42-.11c.19-.09.38-.1.57-.04.06.03.16.07.31.1.18,0,.31,0,.39.02.15.03.28-.04.4-.21l.14-.2h.06s.12.07.12.07c.12.05.17.13.14.26v.1s.08.28.08.28l.06.04.12.22.02.04c-.05.03-.07.07-.06.12.03.05.05.09.04.11,0,.02,0,.03.02.04.02,0,.03.02.02.04.05-.03.08-.07.09-.11,0-.04,0-.06-.02-.07.02,0,.03,0,.03,0,.03-.02.05-.01.06.01.16.08.29.15.41.22l.05.04c.05.06.11.07.16.03.03-.02.05-.01.06.01.02,0,.04,0,.06.01h.06c.08.03.16.07.24.13.02,0,.05.03.08.08.02,0,.03.02.02.04.02,0,.02.01,0,.03l.06.04s.02.04.02.04c.03-.02.05-.01.06.01,0,.02.02.04.09.05.02,0,.04-.01.04-.06-.02,0-.03-.02-.02-.04.02,0,.03.02.02.04l.14.13.23.31c.09.11.15.23.18.37-.01.06,0,.12.06.18.06.03.1.12.11.25v.03c.1.11.18.18.24.22.02.03.03.03.03,0,.02-.02.05-.02.07-.02h.06c-.03.05-.01.12.05.22.03.05.05.08.05.08.03.05.05.06.06.01h.03s.03.31.03.31v.26c.06.25.05.56-.02.91-.03.13-.05.34-.07.64-.03.15-.06.25-.1.31-.02.08-.05.19-.1.31-.03.13-.08.27-.16.42-.05.14-.11.27-.18.39-.05.12-.1.25-.15.39-.02.02-.04.05-.05.09.02.03.01.05-.01.06-.04.1-.1.22-.17.36-.07.12-.14.24-.21.38-.07.12-.11.23-.14.33-.02.08-.05.14-.1.17,0,.02-.02.03-.04.02,0,0,0-.01,0-.03-.02-.03-.04-.03-.06-.01,0,0,0,.01,0,.03l-.28.4c-.08.09-.19.23-.32.42l-.13.17-.26.27-.27.33-.57.5c-.05.05-.12.12-.2.19-.06.07-.13.16-.22.25-.02,0-.03,0-.04.02,0,.02,0,.03,0,.03l.09.02.14-.04-.09.11c-.03.06-.09.08-.18.06-.17-.02-.35.07-.54.24l-.04.06v.06c-.03.06-.09.15-.2.25-.06.1-.27.27-.6.52l-.86.5c-.23.15-.38.23-.45.26-.1.04-.21.11-.34.19-.13.08-.22.15-.27.2-.03.02-.04.05-.05.09,0,.02-.02.04-.04.06v.06s-.4.44-.4.44c-.08.07-.17.07-.26,0-.05-.08-.11-.13-.19-.17h-.03c-.08.04-.17.12-.28.23-.23.15-.4.31-.53.48l-.04.02s-.03,0-.03,0c0-.02,0-.03,0-.03h-.03s-.16.12-.16.12c-.03.04-.05.04-.07.02-.11-.11-.21-.11-.29,0l-.04.06c-.05.03-.1.03-.16,0-.03-.05-.09-.07-.18-.07l-.32-.04-.37-.11s-.05-.01-.09-.02c-.04,0-.09,0-.14.04,0,.02-.02.03-.04.02l-.64-.2ZM137.4,12.87l-.04-.11h-.03s.07.14.07.14v-.03ZM137.63,12.89c-.03-.05-.05-.08-.05-.08h-.03s.07.11.07.11v-.03ZM137.03,12.01s.07,0,.1-.01l-.09-.05-.07.02.06.04ZM137.23,12.15s0-.06-.02-.07c-.02,0-.04,0-.06-.01h-.03s0,.02,0,.02c.02,0,.03,0,.03,0l.06.04s0,.03,0,.03c.02,0,.03,0,.03,0v-.03ZM137.92,13.51c.07,0,.16,0,.29.03v.03s.19-.02.19-.02c.02,0,.03,0,.03,0,0-.02,0-.03,0-.03t0,0s0-.03,0-.03c-.04-.03-.07-.04-.09-.02-.02.02-.05.01-.06-.01-.04.08-.08.08-.13,0l-.22-.05-.16-.03-.04.06h.06s.06.03.06.03l.06.04ZM137.75,12.91l.02.04.04-.02h-.03s-.01-.04-.05-.05h-.06s.03,0,.03.02l.05.04v-.03ZM136.72,11.35l-.02-.04v.06s0,.07,0,.07l-.02-.04c-.03-.07-.03-.12,0-.13t0,0s0-.03,0-.03l-.03-.3s-.03-.02-.02-.04c0,.04-.01.06-.01.06v.13s0,.06,0,.06c0-.02,0-.03-.03-.04,0-.02,0-.03-.02-.04v.03s-.01.03-.01.03c.01.05.02.09.04.14.01.05.03.09.07.15,0,.02.01.04.05.04,0,.02.01.04.06.04h.03s-.06-.17-.06-.17ZM138.12,13.03l.07-.02-.04-.14s-.05,0-.1.01c-.03.02-.04.05-.05.09l.02.04.09.02ZM137.71,12.35s.03,0,.04-.02c0-.02.01-.02.03,0l.06.04h.06s0-.02-.02-.02l-.06-.04h.06s.02.02.06.03l.11-.04c.05-.03.08-.03.09.02h.03s0-.03-.02-.03c0-.07-.06-.09-.15-.06-.02.02-.06.02-.1.01l-.28-.09s-.06,0-.11.04h-.03s-.06-.02-.06-.02l-.09-.02h-.03s0,.02,0,.02c.02,0,.03,0,.03,0,.02.03.05.04.09.05.04,0,.07.03.09.05.02.03.03.04.06.04.05-.01.08-.02.1-.01,0-.02,0-.03,0-.03.02,0,.03.02.02.04,0,.02,0,.03,0,.03.02,0,.03,0,.03,0ZM138.13,12.37s.06.01.06.01c.06.01.11.01.13,0,0,0,.03-.02.08-.05l-.05-.08h-.1s-.03,0-.03,0v.03c.03.05.02.07-.02.06l-.07.02ZM138.71,12.4s.03,0,.04-.02l-.06-.04-.07.02-.04.02s-.01,0-.03,0c0,0,0,.01,0,.03h.03s.13,0,.13,0ZM139,13.51c.35-.08.56-.13.65-.15.16-.03.29-.1.4-.21.02,0,.03,0,.04-.02h-.03c-.05.03-.12.05-.22.08,0,.02-.02.03-.04.02,0,.02-.02.03-.04.02,0,.02-.03.03-.07.02,0,.04-.05.06-.11.04l-.06-.04.02.07v.03s-.04,0-.04,0l-.12-.03v.03s-.09,0-.14,0c-.05.01-.08,0-.09-.02h-.06s0,.02,0,.02c.02.03.01.05-.01.06,0,0,0,0-.03,0-.04,0-.07,0-.1.01-.1-.02-.2,0-.28.07,0,0,0,.01,0,.03,0,0,.01,0,.03,0l.3-.03ZM138.82,12.98c.05-.03.09-.02.12.03l.07-.02-.06-.04.07-.02.06.04s.06,0,.07-.02c0-.02.02-.03.04-.02h.03s.02-.02.04-.02c.06.01.12,0,.17-.03l.07-.02v.03s.24-.08.24-.08l.14-.04.02-.09-.07.02-.21.05c-.05.03-.14.06-.28.07-.13.01-.24.04-.31.06l-.21.05s-.03,0-.04.02h.03ZM139.36,12.28v-.03c-.06-.01-.11-.01-.16,0v.03s.02,0,.02,0h.13ZM142.06,15.09c-.03-.05-.05-.08-.05-.08,0,0,.02-.02.08-.05,0,.02.01.06.04.11l-.07.02ZM140.71,13.03l.14-.07.04-.02h-.03s-.18.05-.18.05v.03s.03,0,.03,0ZM140.34,12.59s.03,0,.04-.02c0-.02.02-.03.04-.02l.11-.07s.06-.02.1-.01c.05-.01.07-.04.08-.08h.03s.1,0,.1,0c.03-.02.06-.03.11-.04.07-.03.11-.06.12-.1l.04-.02c.08.02.13,0,.15-.07v-.06s-.03,0-.06.02c-.02,0-.03,0-.03,0-.05.03-.08.06-.08.08-.14.04-.22.06-.25.08-.02.02-.05.03-.08.05-.02.02-.06.03-.11.04l-.37.18-.04.06.09.02ZM140.98,12.07c.11,0,.19-.02.25-.08l.04-.02h-.03s-.03-.01-.03-.01l-.07.02-.15.07-.04.02h.03ZM141.37,11.93s.06,0,.11-.04l-.02-.04-.11.07h.03ZM141.55,12.59l.11-.07c.05-.03.09-.05.11-.04l.18-.06.24-.18v-.03s-.02,0-.02,0c-.2.13-.3.2-.3.2-.04,0-.07.02-.08.08-.07,0-.12.02-.17.03-.02.02-.05.03-.08.05l-.04.06.07-.02ZM141.52,11.86s.08,0,.1-.01c0,0,.05-.03.15-.1.02,0,.03,0,.03,0,0-.02,0-.03,0-.03h-.06s-.22.1-.22.1v.03ZM141.37,12.09s.05-.03.15-.1c.04,0,.06,0,.07-.02.14-.06.25-.11.33-.16,0,0,.02-.02.08-.05.02,0,.06,0,.11-.04l.41-.24s.07-.02.07-.02c0-.02-.01-.05-.05-.08,0-.02,0-.03-.02-.04l-.05.06-.04.06-.6.33s-.07.04-.15.07c-.07.03-.12.07-.16.13h-.1s-.07.03-.07.03l-.04.02v.03s.05.01.05.01ZM142.29,12.23c.06-.05.1-.09.12-.1h-.03s-.11.04-.11.04c-.02.02-.04.03-.04.06.02,0,.03,0,.03,0h.03ZM142.24,11.53s-.03,0-.03,0c0-.02,0-.03,0-.03l-.11.07s.03.02.02.04l.11-.07ZM142.31,11.51s.04-.02.04-.02c.03-.02.04-.03.04-.06v-.03s-.11.07-.11.07c.02,0,.03.02.02.04ZM142.52,12.08s.06,0,.11-.04c.06-.05.09-.1.1-.14l.02.04s.09,0,.13,0c.05-.03.08-.07.09-.11l-.02-.04c-.1.07-.18.1-.22.12-.1.07-.18.1-.22.12v.06s.02,0,.02,0ZM142.77,12.26l.26-.14v-.03s0,0-.02,0t0,0l-.26.14v.03s.02,0,.02,0ZM141.85,10.76l.26-.14-.03-.04h-.03s.03-.01.04-.03l.18-.06s.02-.03.04-.02l-.06-.04-.14.04-.2.19-.09.11h.03ZM142.63,11.41s.06,0,.11-.04l-.06-.04-.04.06v.03ZM142.89,11.27c.05-.03.09-.05.11-.04.03-.02.03-.03,0-.03,0-.02,0-.03-.02-.04,0,0,0,.01,0,.03-.02,0-.06,0-.11.04v.03s.02,0,.02,0ZM143.44,11.89s.03-.07.05-.09c0,0,0,0-.03,0,0,0,0-.01,0-.03l-.08.08.06.04ZM142.63,10.33s-.04.01-.03,0l.11-.07s.01,0,.03,0l-.11.07ZM142,12.03s-.01-.04,0-.03c.04,0,.06,0,.07-.02.05-.03.08-.05.08-.05,0-.04.04-.06.11-.04l.04-.02.34-.19.08-.08.53-.31s.06-.04.11-.07c.05-.05.11-.09.15-.1.05-.01.08-.04.11-.07.06-.05.1-.09.12-.1.05-.01.08-.04.11-.07.03-.04.06-.06.08-.08.13-.08.19-.13.2-.15l.08-.08.34-.22.09-.11h-.03c-.06-.02-.1,0-.11.04l-.48.39-.58.43c-.18.11-.27.17-.27.17,0,0-.13.08-.38.25-.25.16-.38.25-.38.25l-.26.14c-.08.05-.11.09-.09.11-.01-.05-.05-.04-.13,0v.06s.06-.02.06-.02ZM143.57,11.75h.03c.08.02.13,0,.15-.09,0-.02.02-.03.04-.02v-.03s-.05-.04-.05-.04c-.03.04-.1.09-.2.15v.03s.02,0,.02,0ZM143.18,11.11c.13-.08.19-.12.19-.12v-.03s-.02,0-.02,0c-.07.03-.13.07-.19.12h-.03s.06.04.06.04ZM144.07,12.02s.03,0,.03,0c0-.02,0-.03,0-.03h-.03s-.15.09-.15.09c0,0,0,.01,0,.03.02,0,.03,0,.04-.02l.11-.07ZM143.76,10.71s.07,0,.08-.05l.11-.07h-.03s0-.04,0-.04l-.04.02h-.03s-.09.03-.12.07c0,.02-.02.04-.04.06.02,0,.03.02.02.04l.04-.02ZM143.3,11.63l.09-.11c.06.01.11,0,.15-.07l.12-.07c.14-.06.23-.12.27-.2.08-.05.11-.07.11-.07.05-.01.09-.05.12-.1.05-.05.11-.1.16-.13,0-.02,0-.03,0-.03.03-.02.05-.03.08-.05l.24-.21.26-.3c.05-.03.11-.11.18-.22l.04-.02.04-.02-.07.02s-.02.02-.08.05c-.09.11-.15.18-.17.19l-.41.4h-.03s-.05.03-.15.09l-.36.28c-.21.17-.32.27-.33.29-.02,0-.03.01-.04.06,0,.02-.03.05-.08.08l-.04.06h-.03s-.24.17-.24.17c0,0,0,.01,0,.03.02,0,.03,0,.04-.02l.15-.07ZM144.15,10.43v-.03s-.02,0-.02,0c-.02,0-.06,0-.11.04l.02.07.11-.07ZM144.64,11.03s.03,0,.04-.02l.19-.12-.02-.04-.2.15v.03ZM138.47,11.11c.17.02.35-.01.54-.08.17-.07.3-.09.4-.04.1.02.18.03.22.02.24-.01.52-.04.84-.08l.42-.14c.27-.05.51-.15.72-.3.11-.09.36-.22.77-.39.02,0,.03,0,.04-.02.02.03.04.04.06.04.02,0,.04,0,.06.01h.03s-.04.03-.04.03c-.06.07-.11.12-.16.13-.03.02-.04.05-.05.09.02.03.02.04.02.04l.09.02s.02-.03.04-.02l.04-.02-.04.02-.05.09s.03-.03.07-.02l.04-.02c.24-.1.43-.2.56-.31l.12-.1s.04-.03.04-.06c0-.04.03-.07.05-.09.07-.03.16-.07.26-.14.11-.09.2-.15.27-.2.03-.02.05-.03.08-.05.03-.04.05-.08.06-.12.07-.1.13-.16.2-.19l.24-.21.11-.07c.09-.11.2-.21.32-.29.03-.02.04-.05.05-.09l.15-.1.11-.07.05-.09s.04-.03.04-.06c0-.02,0-.03,0-.03.04,0,.07-.02.08-.08l.06-.12c.05-.03.09-.05.11-.04,0-.07.01-.11.06-.12v-.03s.05-.11.18-.19l.04-.06h-.06s-.07,0-.07,0h-.03s0-.04,0-.04l.04-.02s.07,0,.07-.02l.24-.21.07-.02h-.06s-.02-.05-.02-.05l.1-.14s.06-.07.09-.11c.03-.06.07-.12.1-.17,0-.04.03-.07.05-.09.04,0,.07.03.09.05.04,0,.06,0,.07-.02.06-.16.12-.3.19-.42.07-.12.12-.21.16-.29.02-.02.08-.12.17-.32v-.19s.21-.64.21-.64c.01-.06,0-.1-.04-.11-.02,0-.03,0-.03,0,0-.02.02-.04.04-.06l.04-.06-.06-.04h-.06s-.38-.06-.38-.06h-.03s.04-.03.04-.03l.14-.04s0-.03,0-.03c.02,0,.03,0,.03,0h-.03s-.28-.07-.28-.07l-.28-.06-.46.03h-.06s.07-.03.07-.03l.04-.02s0-.07-.05-.08c-.02,0-.05-.02-.09-.05-.01-.05-.04-.05-.09-.02l-.07.02c-.1-.06-.2-.08-.32-.04l-.27.04-.04.02.02.04h.03s.03.02.02.04l-.2.02c-.06-.01-.11-.01-.13,0-.06.05-.12.09-.19.12-.16.14-.29.23-.39.28l-.11.07-.34.06-.04.06h.06s.33-.01.33-.01h.06s-.04.04-.04.04c-.25.03-.4.05-.47.06l-.57.07s-.06.04-.11.07c-.03.02-.06.02-.1.01-.12.04-.19.1-.2.19l-.08.05-.12-.06s-.02-.06-.01-.1c.03-.04.04-.06.04-.06,0-.04,0-.07-.05-.08-.15-.03-.29.01-.42.14l-.07.02s-.1.01-.18.06c-.06.05-.09.1-.1.14l-.04.06c-.05.03-.08.06-.08.08l-.13.14-.66.81-.41.53-.33.48-.73,1.12c-.07.1-.19.31-.37.64l-.25.57c-.06.16-.17.45-.35.87h.03s-.02.1-.02.1c-.04.17.03.27.2.3ZM144.1,11.73s.06-.03.11-.04c.05-.03.07-.08.07-.15l.25-.11c.06-.07.11-.09.14-.04h.06s-.02-.02-.02-.02l-.02-.07c.13-.08.21-.15.24-.21l.08-.05s0,.01,0,.03c0,0,.01,0,.03,0v.03s0-.03,0-.03c.02,0,.03,0,.03,0-.01-.05,0-.1.07-.15.02-.02.04-.01.03,0,.02,0,.04,0,.06.01l.16-.13s0-.03-.02-.04h-.03s.08-.06.08-.06c.02.03.04.03.06.01.03-.02.04-.02.04-.02.05-.03.11-.09.17-.16l.04-.06-.07.02h-.03s0-.04,0-.04l.32-.29v-.06s-.05-.01-.05-.01c-.06.07-.11.12-.16.13l-.61.56-.06.12-.36.28c-.1.07-.15.1-.15.1-.03.06-.09.09-.15.1l-.1.14-.22.12v.03s.02.04.02.04ZM145.25,11.23c.05-.03.11-.09.17-.16,0,0-.05.03-.15.1v.03s-.01.03-.01.03ZM144.7,10.16l.08-.05.08-.08v-.03s-.03,0-.03.02l-.11.07-.04.02v.06s.02-.02.02-.02ZM143.96,11.47l.07-.02s.01.05.06.01l.12-.1s0-.03,0-.03c.02,0,.03,0,.03,0v-.03c-.03-.05-.02-.08.03-.09,0,0,.02,0,.07-.02.05-.01.05-.04.02-.09,0,0,0,.01.02.04.04,0,.06-.02.05-.09h.03s.1-.06.17-.15c0-.02.02-.03.04-.02,0,0,.06-.04.19-.12l.33-.32.32-.29.3-.33v-.06s.05-.05.08-.02h.03s.04-.07.09-.1c.06-.07.12-.14.17-.19.06-.07.11-.13.14-.17.02-.02.03-.04.01-.06,0-.02.02-.04.04-.06,0-.02,0-.03-.03-.04h-.1s-.14.21-.14.21l-.18.22-.12.1-.21.22s-.03,0-.04.02t0,0s-.03.07-.05.09l-.09.11-.06.12s-.07-.03-.1.01c-.02.02-.04.03-.04.06-.08.05-.09.1-.03.16l-.14.04c-.06.07-.12.13-.17.16-.1.07-.24.19-.41.37l-.12.1c-.12.04-.2.13-.26.27l-.18.06-.04.06.07-.02ZM145.49,10.3h-.03c-.05.03-.11.08-.17.15v.03s.2-.19.2-.19ZM145.1,9.82s0-.03-.02-.04c-.05.03-.08.06-.08.08v.03s.11-.07.11-.07ZM145.05,9.45s0-.03-.02-.04l-.08.08v.03s.11-.07.11-.07ZM142.49,6.44s-.03-.03-.02-.07c.1-.15.21-.4.32-.75.06-.07.11-.12.16-.13,0,0,.09-.06.27-.17v-.03s.03-.04.05-.06c.02-.02.05-.02.07-.02v.03s-.24.18-.24.18c-.11.11-.22.29-.32.55l-.26.44-.04.02ZM145.13,9.37c.05-.03.08-.06.08-.08,0-.02,0-.03-.02-.04,0,.02-.03.05-.08.08.02,0,.03.02.02.04ZM145.66,10.86s0-.03,0-.03c.02,0,.03,0,.03,0l.12-.1s.05-.04.08-.08c.03-.04.08-.05.14-.04v-.03s.03-.02.08-.05v-.06s-.01-.04-.01-.04h.06s.04-.01.04-.01c-.02-.03-.01-.04,0-.03.03-.02.05-.02.07-.02v-.03s.07-.12.07-.12c.05-.01.09-.05.12-.1.04-.06.07-.1.09-.11v-.03s-.03,0-.03,0l-.04.06-.5.48-.18.22s-.04,0-.07.02c-.03.02-.05.03-.08.05v.06ZM145.26,9.23s.03,0,.04-.02l.17-.16v-.03s-.06.02-.06.02l-.13.14v.06ZM145.48,8.99s.03,0,.03,0c0-.02,0-.03,0-.03l.07-.02.09-.11h-.03s-.13.13-.13.13c-.02,0-.03,0-.04.02ZM145.64,9.28c.14-.12.21-.2.21-.22l.13-.17s.02-.03.04-.02c.02-.02.04-.02.04-.02-.01-.05.02-.11.11-.21v-.03s0,0-.03,0c0,0,0,.01,0,.03-.03.02-.08.08-.17.19l-.13.14h-.03s.03-.13.03-.13c.02,0,.03.02.02.04l.04-.06.05-.09.05-.09v-.03s0,0-.03,0c0,0,0,.01,0,.03l-.14.2c-.05.03-.08.06-.08.08.01.05,0,.1-.03.16,0,.04-.01.07-.02.09v.06s-.05.02-.05.02h-.03s.02.03.02.03ZM146.18,9.66l.09-.11.03-.13c.08-.05.15-.13.22-.25v-.1s-.04,0-.04,0v.03s-.02.06-.02.06l-.1.17-.21.22-.04.06v.03s.02,0,.02,0c0-.02,0-.03,0-.03.02,0,.03,0,.03,0v.06s.02-.02.02-.02ZM146.77,9.82l.08-.08v-.03s-.02,0-.02,0l-.15.1.02.07h.03s.04-.05.04-.05ZM146.41,9.06l.09-.11v-.03s-.03,0-.03,0l-.12.1v.06s.06-.02.06-.02ZM145.98,10.14s.05-.03.08-.05c.03-.04.05-.07.05-.09,0-.04.03-.07.05-.09.03-.02.05-.03.08-.05.03-.04.07-.08.13-.14.06-.07.12-.15.18-.22l.25-.27.4-.5s.03-.03,0-.03c0-.02.02-.03.04-.02v-.06s.14-.14.14-.14l-.03-.04s0,0-.03,0c0,0,0,.01,0,.03l-.22.25-.14.2-.13.14s-.05.05-.09.11c0,.04-.03.07-.05.09-.03.04-.07.07-.12.1-.03.04-.06.08-.1.14-.17.18-.29.32-.35.42-.05.03-.08.06-.08.08,0,.04-.03.06-.08.05v.03s.01.07.01.07ZM143.1,3.76s.03,0,.04-.02c.02,0,.06,0,.11-.04.08.02.15.02.19,0,.02,0,.03,0,.04-.02,0-.02.02-.03.04-.02,0,0,.03-.02.08-.05v-.03s-.05-.04-.05-.04l-.14.04s-.02,0-.07.02c-.02.02-.03.04-.01.06,0,0,0,.01,0,.03,0-.02,0-.03-.03-.04v-.03s-.03,0-.03.02l-.15.07s-.02.03-.04.02c0,0,0,.01,0,.03,0,0,0,0,.03,0ZM146.41,7.98s.03-.03,0-.03c0-.02,0-.03-.02-.04-.02,0-.03,0-.04.02l-.13.17.02.04.17-.16ZM143.73,3.6s.03,0,.04-.02c-.02-.03-.04-.04-.09-.05,0,0-.01,0-.03,0l.02.04s.03.02.02.04l-.04.02.07-.02ZM146.41,8.76s.05-.03.08-.05c.03-.02.04-.05.05-.09s.03-.07.05-.09c.03-.04.05-.07.05-.09.06-.05.1-.08.15-.07.03-.02.03-.03,0-.03,0-.02,0-.04.01-.06.07-.12.13-.19.18-.22,0-.04.03-.07.05-.09.03-.04.06-.06.08-.08-.04-.03-.04-.04-.02-.04s.03,0,.04-.02c0-.04,0-.06-.02-.07l-.07.02-.04.06s-.04.06-.12.1c-.06.05-.12.14-.19.25-.06.07-.13.19-.21.35l-.1.17v.03s.02,0,.02,0ZM146.53,7.9s.04-.08.09-.11c.08-.05.1-.1.07-.15,0,0,0-.02.01-.06l-.02-.07h-.03s-.02.09-.02.09v.03s-.02.06-.02.06l-.09.11s-.01,0-.03,0c0,0,0,.01,0,.03l-.07.02s.02.03.05.08l.07-.02ZM146.56,9.12s.02-.02.08-.05c.02-.02.05-.04.08-.08.03-.06.06-.12.07-.18v-.03c.11-.07.18-.17.21-.32.06.01.1-.02.12-.1,0-.02.02-.05.05-.09.03-.06.04-.1.03-.13l.05-.09c.13-.08.17-.18.13-.3v-.03c.07.01.08,0,.05-.06v-.06s.05,0,.05-.02h-.03s-.07.01-.07.01c-.13.19-.19.34-.19.45,0,.04-.04.1-.1.17-.1.07-.13.15-.09.24-.06-.01-.1.03-.13.14l-.13.14h-.03s0-.04,0-.04l.15-.26.02-.09-.08.05s-.02.06-.04.06l-.06-.04.02.07c.06.03.06.07.01.1-.06.07-.09.12-.1.14-.02,0-.03,0-.04.02.02.03.02.04.02.04.07,0,.09,0,.06.04,0,.02-.02.03-.04.02,0,.02-.02.05-.05.09,0,.04-.04.07-.08.08,0,.02,0,.06.04.11ZM144.07,3.54v-.03s-.02,0-.02,0c-.04,0-.08,0-.1.01h-.03s0,.06.05.07l.11-.04ZM146.27,7s0,0-.03,0t0,0l-.07.02.06.04.04-.06ZM146.51,6.16v-.06c.06-.03.11-.09.15-.17s.06-.14.07-.18c0-.02,0-.03,0-.03.02,0,.03,0,.03,0v.03s-.12.37-.12.37l-.04.06s-.03.02-.08.05l-.02-.07ZM148.07,8.17l.08-.08-.02-.07h-.03s-.09.1-.09.1v.06s.05-.02.05-.02ZM147.63,7.19s.03-.07.05-.09l-.03-.04h-.03s-.01,0-.03-.01c0,0,0,.01.02.04,0,.04,0,.08.01.1ZM147.64,7s-.01.05,0,.03c.02-.02.04-.02.04-.02.04.03.06.03.06.01.03-.02.04-.02.04-.02,0-.02,0-.03-.02-.04l-.11.04ZM147.95,7.55c.08-.09.14-.18.15-.26l-.02-.07-.04.06-.12.27h.03ZM147.75,6.79s.06,0,.11-.04c-.04,0-.06-.02-.06-.04-.04,0-.07,0-.08.05l.02.04ZM148.09,7.19s0-.03,0-.03c.02,0,.03,0,.03,0,.01-.06.05-.11.1-.14l-.03-.04h-.03s-.07.14-.07.14c0,0,0,.02-.01.06ZM146.81,4.79c-.03-.05-.05-.08-.05-.08v-.06s.04,0,.04,0l.04.11-.04.02ZM148.35,6.73l-.02-.07-.05.09v.06s.07-.08.07-.08ZM148.37,6.37s0-.03-.03-.04v.03s-.06.11-.08.21l.11-.21ZM148.78,6.59s.03-.04.01-.06c0-.04.02-.07.02-.09h-.03c-.01.06-.04.11-.07.14l.02.07.04-.06ZM146.24,2.57h.03s.02.04.02.04c.03-.02.04-.03.04-.06l.04-.02s0-.03,0-.03c.02,0,.03,0,.03,0h-.03c-.08-.02-.15-.03-.19-.02,0,0-.01,0-.03,0,0,0,0,.01,0,.03l.02.04h.06ZM148.44,6.19c.03-.13.08-.2.15-.23,0,0,0-.02.01-.06v-.03s-.04.06-.04.06h-.03s.07-.32.07-.32v-.06s.05,0,.05-.02c0,0-.02-.03-.05-.08l-.04.06v.06s-.06.35-.06.35l-.12.27v.06s.06-.05.06-.05ZM148.22,5.36v-.03s.03-.13.03-.13v-.03s-.06-.01-.06-.01v.03s-.04.16-.04.16l.02.07.04-.06ZM147,3.16l-.08-.08h-.06s0,.02,0,.02c0,.04,0,.06.02.07l.12.03v-.03ZM146.66,2.76s.08,0,.1-.01v-.03s-.02,0-.02,0l-.07.02s-.01,0-.03,0c0,0,0,.01,0,.03,0,0,0,.01,0,.03,0,0,.01,0,.03,0v-.03ZM146.66,2.6s.04,0,.07-.02c.05-.01.08,0,.09.02l.08-.05h-.06c-.06-.03-.12-.03-.16-.02-.08-.02-.15-.02-.19,0v.03s.18.04.18.04ZM148.25,5.1s.03,0,.03,0c0-.02,0-.03,0-.03v-.03s-.02,0-.02,0c0-.02,0-.03,0-.03l.05-.09-.02-.07s-.02.03-.04.02l-.06.12c-.01.06,0,.1.04.11ZM147.2,2.97v-.03s-.04,0-.06-.01c0-.02,0-.04.01-.06h-.03c-.04.05-.1.07-.21.05v.06s.11.03.11.03c0,.02,0,.03,0,.03.02,0,.03,0,.03,0l.15-.07ZM147.09,3.18c.06.01.1,0,.11-.04,0-.02.02-.04.04-.06.03-.02.05-.02.07-.02l.24.09h.03s.01-.06.01-.06h-.06s-.06-.04-.06-.06c-.04-.03-.08-.05-.12-.06-.02-.03-.04-.03-.06-.01l-.11.07s0,.06-.04.06c0,0-.03.02-.08.05l.02.04ZM147.52,3.31c.08.02.13,0,.15-.07v-.03s-.06-.01-.06-.01c-.03.04-.08.05-.14.04-.04-.03-.06-.03-.06-.01h-.03s-.06-.05-.06-.05h-.06s.05.06.05.06l.21.08ZM148.71,4.61l-.04-.11v.06s0,.07,0,.07l.04-.02ZM147.6,18.97c-.03-.05-.11-.11-.22-.18-.03.04-.06.03-.09-.02-.14-.07-.21-.15-.21-.24l-.05-.21-.04-.14v-.06s.02-.08,0-.1h-.03s0-.08-.03-.18c0-.02,0-.05-.01-.1,0-.02.02-.06.06-.12.02-.02.03-.08,0-.19-.01-.05-.04-.05-.09-.02v.03s-.04-.02-.03-.04c.03-.13.04-.22.03-.29,0-.02-.01-.06-.04-.11v-.06s.04.04.04.04h.03c.01-.06,0-.09-.01-.09-.02,0-.03-.02-.02-.04.01-.06.03-.1.06-.12,0-.02.01-.05.02-.09v-.03s-.03.02-.03.02v.06s-.04,0-.04,0c-.02-.03-.02-.07,0-.13-.01-.05,0-.08.02-.09,0-.02,0-.04.01-.06h.03c.05-.03.08-.05.08-.07,0-.02,0-.06-.04-.11-.01-.05,0-.11,0-.19.02-.08.06-.17.12-.27.04-.1.07-.17.08-.21.03-.04.06-.08.1-.14.03-.06.08-.11.13-.17.07-.12.11-.18.11-.21v-.03s0,0-.02,0c0,0,0,.01,0,.03l-.14.2c-.06.07-.09.13-.1.17l-.07.02v-.06s.06-.1.12-.17c.01-.06.05-.13.11-.21.04-.08.08-.15.11-.21.03-.06.07-.12.1-.17l.15-.26s.02,0,0,0c0-.02,0-.03,0-.03v-.06s.06-.1.12-.17v-.03s-.02,0-.02,0l-.04.06-.04.02v-.03s0,0-.02,0c0,0,0-.01,0-.03v.03s-.14.17-.14.17l-.04.02v-.03c.02-.08.05-.14.08-.18.01-.06.03-.1.06-.12.03-.04.06-.07.09-.11l.04-.19h-.03s-.03,0-.04.02l-.07.02s0,0-.03,0c0-.02.02-.03.04-.02.02-.08.05-.13.1-.14v-.03c.04-.08.1-.17.16-.26.06-.1.11-.16.14-.2.06-.07.09-.13.1-.17.03-.02.03-.03,0-.03,0-.02,0-.04.01-.06-.04,0-.06,0-.07.02,0,0-.02.02-.08.05l.02-.09.09-.11v-.03s-.02,0-.02,0c0,.04-.04.08-.09.11v.03s-.01-.03-.03-.04l.06-.12v-.03s-.03,0-.03.02c-.05.03-.08.08-.1.14-.02,0-.03,0-.04.02h.06s0,.02,0,.04c0,0,0,0,.03,0-.02,0-.03,0-.04.02-.06-.03-.1,0-.11.07l-.34.35v-.03s.15-.23.15-.23c.12-.17.24-.34.34-.52l.28-.4.04-.06s-.06,0-.07.02l-.13.17-.04.06s.02-.06.04-.06l.42-.6c.15-.17.35-.44.6-.82l.32-.42c.09-.13.2-.27.32-.42.12-.17.24-.35.35-.55.05-.12.1-.22.16-.29s.11-.14.14-.2c.19-.26.32-.47.39-.6l.45-.72.34-.52c.14-.23.23-.41.28-.53l.13-.14c.19-.29.35-.54.46-.75.04-.08.12-.19.24-.34l.47-.98.32-.42.15-.26.13-.17.08-.05c.01-.06.05-.15.12-.27l.25-.24s.04-.05.05-.09c.05-.03.09-.05.11-.04.06.01.14,0,.23-.02v-.03c.04-.06.07-.14.09-.24.01-.06.08-.1.19-.12.04,0,.08,0,.1-.01.03-.02.05-.03.08-.05,0-.02.03-.05.08-.08,0-.02.02-.03.04-.02l.02-.09.07-.02-.04.02.02.07s.03,0,.03,0c0-.02,0-.03,0-.03.04,0,.06.02.06.04h.03s.03.01.03.01v.03s-.14.14-.14.14l-.02.09.04-.06s.06-.04.18-.06c.02,0,.06.01.12.03.09,0,.16-.03.21-.08l.04-.02.02.07s0,.08.01.1c.05-.03.08-.05.08-.05.03-.02.12-.1.29-.27.09-.02.15-.05.18-.09,0,0,.01,0,.03,0,.02,0,.03.02.02.04,0,.07.06.09.15.07,0-.02.02-.03.04-.02l-.05.06s-.02.04-.04.06c-.02.02-.03.04-.01.06.02.03.06.04.12.06.08.02.12-.02.12-.1,0-.04.03-.06.08-.05.06.01.12,0,.17-.03.05-.01.1-.01.16,0,.06.01.11.04.15.07,0,0,.02.03.05.08.01.05,0,.1-.06.15-.03.04-.05.07-.05.09,0,.04,0,.06.02.07v.03s-.15.07-.15.07v.06c.07.11.09.27.04.5l-.05.25c-.04.17-.13.39-.27.66-.05.14-.11.36-.17.65l-.04.19c-.05.25-.08.53-.08.83,0,.15,0,.4-.03.75,0,.09-.02.17-.06.25-.02.08-.02.17-.02.26-.02.1-.04.27-.04.48-.04.3-.07.67-.08,1.13l-.06.87-.05.68c-.02.3-.05.53-.09.7-.03.34-.06.6-.1.76,0,.02,0,.03.02.04-.03.13-.04.3-.04.51l.03.17c.03.07.03.25.02.53,0,.04-.02.1-.04.19,0,.07-.02.13-.07.18l.02.07.07-.02.24-.34.32-.42.26-.3.18-.22.29-.3.22-.28.15-.23s.11-.14.23-.31l.42-.56c.03-.06.07-.11.1-.14.03-.06.07-.11.1-.14l.19-.25.47-.65.21-.35.42-.56.37-.51.43-.63.59-.76c.07-.1.13-.18.19-.25.08-.07.14-.13.17-.19.12-.13.27-.32.45-.59l.42-.56.11-.07-.05.09-.25.37-.04.06c-.07.03-.15.12-.22.28,0,.02-.04.07-.1.14-.04.08-.12.19-.24.34-.06.07-.12.13-.17.16,0,0,0,.01,0,.03,0,0,.01,0,.03,0h.03s.11-.2.11-.2l-.03.13-.02.09s-.04.03-.04.06c.02.03.05.03.09.02.05-.01.06.01.05.08-.02-.03-.04-.03-.06-.01-.02.02-.04.02-.04.02v.06s.01.04.01.04c.08-.05.11-.09.09-.11.09-.02.14-.08.13-.17,0,0,0-.01-.03-.04,0-.04.04-.06.08-.05.01-.06.04-.09.08-.08.02,0,.04-.01.05-.06-.03-.05-.02-.07.04-.06v-.03s-.02-.04-.02-.04c.02-.02.04-.03.04-.06l.2-.32.13-.17s.08-.08.17-.19l.05-.06.09.05h.03s.03-.03.01-.06h-.03s-.1,0-.1,0l.1-.14.07-.02h.03c.01.05.04.06.09.03l.13-.14s.02-.06.04-.06l.04-.06v.06s-.21.32-.21.32l-.04.06c-.05.03-.07.06-.05.09-.03.02-.04.05-.05.09.02.03.01.05-.01.06v.03s-.02,0-.04,0c0,0,0-.01,0-.03v-.03s.01-.03.01-.03v.03s-.1.11-.1.11c-.05.03-.05.07.01.1v.06c-.07.07-.11.14-.12.21,0,0-.01.02-.04.06,0,.02.01.04.06.04l-.02.09s-.03,0-.04.02h.06s.13-.12.13-.12c.08-.07.19-.2.31-.39l.15-.23s0-.03,0-.03c.02,0,.03,0,.03,0v.03c-.12.13-.21.26-.26.4v.03s.03,0,.03-.02l.19-.29s.1-.12.22-.25c0-.02,0-.03,0-.03.03-.02.03-.04.01-.06,0-.02.02-.03.04-.02.02-.02.04-.05.05-.09l.02.04s-.04.03-.04.06c.02.03.01.05-.01.06-.02.02-.05.09-.08.21l.07-.02.14-.2c.05-.03.1-.04.14-.04l.07-.02.05-.06-.04.02-.07.02s.02-.06.04-.06c0-.02.03-.05.08-.08h.03s.1-.14.1-.14c.02,0,.03,0,.03,0,0-.02,0-.03,0-.03.08.02.14-.04.17-.16,0-.02.02-.03.04-.02.05-.01.08,0,.09.02.07.06.14.08.18.07h.06s-.02.04-.04.04l-.31.23-.23.31s-.03,0-.04.02c.02,0,.03,0,.04-.02.05-.01.1-.06.16-.13l.13-.14c.04-.08.13-.14.27-.17.05-.01.1-.05.16-.13l.11-.07h.06s-.02.11-.02.11l-.04.02h.03s.07,0,.08-.04c-.02-.03-.01-.04,0-.03.03-.02.05-.02.07-.02.06.01.13-.03.19-.12,0,0,.1-.07.31-.2v.03s-.18.19-.18.19c-.03.06-.05.12-.04.19.03.05.06.08.08.08.06.01.07.04.02.07l-.08.08c-.2.13-.38.31-.54.54-.24.32-.44.65-.6.98-.06.1-.13.2-.2.32-.05.12-.1.23-.17.32-.14.25-.32.53-.54.83-.07.14-.2.34-.39.6-.04.06-.1.16-.2.32-.07.14-.16.26-.27.37l-.07.15-.45.72-.32.55c-.17.29-.29.47-.35.55-.05.12-.13.24-.24.37-.13.21-.3.43-.5.65-.09.2-.16.34-.22.41l-.04.06-.19.29-.38.7-.32.55c-.04.06-.07.11-.1.14-.03.02-.05.03-.08.05,0,.04-.03.07-.05.09,0,.02-.04.07-.1.14-.22.3-.38.51-.49.61l-.13.17s-.02.06-.04.06l-.45.59c-.19.18-.32.38-.39.6l-.19.25-.3.49c-.09.09-.16.19-.23.31-.04.1-.1.19-.15.26-.06.05-.1.16-.14.33-.02.08.01.14.09.18.06.03.08.07.07.11.01.05,0,.09-.03.13l-.15.26-.08.24c-.02.08-.06.13-.13.14l-.28.07-.07.02c-.06.07-.14.11-.25.11-.09,0-.14,0-.16,0l-.24.05s-.11-.01-.19,0c-.09.02-.17.02-.23-.02l-.52-.18-.17-.13c-.31-.2-.52-.35-.65-.47-.06-.03-.1-.08-.14-.13-.01-.05-.04-.08-.07-.11-.11-.2-.21-.46-.29-.78-.08-.26-.13-.61-.17-1.05l-.1-.77.02-.55c-.01-.13,0-.25.01-.36,0-.18.01-.46.05-.84,0-.13.02-.31.05-.55.03-.23.06-.44.1-.63,0-.11.01-.2.03-.29.04-.1.07-.2.07-.31l.1-.47c0-.22.02-.38.04-.48l.11-.83c.04-.17.07-.4.09-.7.03-.15.06-.37.08-.67.01-.06,0-.12-.03-.17l-.09.11c-.12.15-.2.26-.24.34-.02.08-.06.17-.12.27-.06.07-.1.13-.13.17l-.24.34c-.09.11-.18.22-.27.33-.09.11-.17.22-.23.31-.22.32-.36.51-.42.56-.03.06-.11.14-.22.25-.01.06-.03.1-.06.12,0,.04-.09.15-.23.31,0,.04-.09.15-.23.31l-.55.73-.49.61-.48.71-.3.46c-.12.17-.2.27-.23.31l-.15.23c-.06.05-.12.14-.19.25-.04.08-.08.17-.12.27-.04.08-.09.16-.15.23-.18.33-.3.64-.37.94l-.1.47-.09.41c-.02.19.02.45.13.78,0,.02,0,.03.02.04.02.03.02.05.02.07.02.03.02.06.01.1-.04,0-.06-.02-.06-.04-.02-.03-.05-.02-.1.01-.06.05-.11.04-.16-.03l-.13-.16ZM146.57,17.54s-.03-.02-.02-.04l.06-.28.02.07-.05.22s.03.04.03.04c-.02,0-.03,0-.03,0ZM146.69,17.56s-.03-.02-.02-.04l-.04-.11.05-.09h.03c.01.05,0,.12,0,.2v.03ZM146.7,17.24s-.04-.05-.09-.02l.06-.12s.02-.03.04-.02c0,.02,0,.03,0,.03l.04.14s-.02.03-.04.02v-.03ZM146.52,16.38l.11-.21v-.03s0,.03,0,.03c-.02.1-.05.17-.08.21h-.03ZM146.96,16.93s.03,0,.04-.02c.03-.02.04-.06.06-.12v-.03s-.03,0-.03.02c-.03.02-.04.06-.06.12v.03ZM147.79,14.76l-.05-.08-.1.14h.03s.11-.07.11-.07ZM147.36,13.26c.09-.11.15-.18.17-.19v-.03s0,.03,0,.03l-.15.23s-.03,0-.04.02v-.06ZM148.06,13.93c.11-.09.18-.22.22-.41h-.03s-.06.07-.09.1c-.02.02-.04.06-.06.12-.02.08-.04.14-.07.18v.03s.03-.02.03-.02ZM149.43,13.08s.03,0,.04-.02l.09-.11v-.03s-.02,0-.02,0c0,.02-.04.07-.1.14v.03ZM150.64,11.54h-.03s-.13.13-.13.13v.03s.03,0,.03,0l.13-.17ZM150.05,10.66c.06-.07.09-.12.1-.14v-.03s-.13.17-.13.17h.03ZM150.74,11.4s.03,0,.04-.02l.04-.02c.19-.26.34-.46.45-.59,0-.02.02-.06.06-.12.04-.06.07-.1.09-.11l.3-.46.22-.28v-.03s-.03,0-.03.02l-.17.19-.02.09s-.03.02-.08.05c-.31.41-.53.73-.66.94l-.23.31v.03ZM153.95,14.12v-.1s-.06.06-.06.06v.1s.06-.06.06-.06ZM154.34,13.09l-.04-.11s0-.03-.02-.04v.03s0,.13,0,.13c.02,0,.03.02.02.04l.04-.06ZM152.18,9.45l.1-.17v-.03s-.13.17-.13.17v.03s.02,0,.02,0ZM154.26,12.82l.04-.06v-.03s0,0-.02,0c0,0,0,.01,0,.03l-.04.02c.03.05.05.08.05.08l-.02-.04ZM154.89,11.9l.02-.09h-.03s-.03-.01-.03-.01l-.06.12h.03s.07-.01.07-.01ZM154.5,11.1l.03-.13-.02-.04v.03s-.05.05-.06.09v.03s.02,0,.02,0h.03ZM154.32,9.85l.02-.09v-.03s-.03,0-.03,0c-.01.06-.03.1-.06.12,0,.02.01.04.06.04v-.03ZM155.04,9.84l.04-.02v-.03s-.06-.01-.06-.01c0,0-.01,0-.03,0,0,0,0,.01,0,.03.02.03.02.06.01.1l.04-.06ZM155.07,9.39s0-.03,0-.03c.02,0,.03,0,.03,0l.04-.06s-.03-.03-.02-.07h-.03s.02.06.02.06c0,.02-.02.03-.04.02v.06ZM158.74,12.11l-.11.07.02.04.09-.11ZM155.05,5.52s0-.03,0-.03c.02,0,.03,0,.03,0v-.1s-.06.06-.06.06l.02.07ZM158.78,11.63c.03-.06.08-.09.15-.1l-.02-.04h-.03s-.11.07-.11.07c0,0,0,.01,0,.03,0,0,0,0-.03,0l.06.04ZM158.97,11.64c.08.02.12-.02.12-.1v-.03s-.01-.07-.01-.07l-.05.06s0,.05-.05.09l-.04.06h.03ZM159.19,11.06l-.02-.04-.11.07.05.08.09-.11ZM159.39,10.62s.03,0,.04-.02c.08.02.13,0,.15-.07,0-.02,0-.03-.02-.04l-.04.02s-.03.05-.07.02l-.04.06v.03ZM160,10.19l.04-.06v-.06s-.04-.04-.04-.04v.03s0,.05-.02.06l-.04.06h.06ZM160.02,9.8l.15-.23h-.06s0,.02,0,.02c.02,0,.03.03.02.07-.05.03-.08.06-.08.08l-.02.09v-.03ZM160.22,9.81s.03,0,.04-.02l.09-.11v-.03s-.02,0-.02,0l-.12.1.02.07ZM160.33,9.58s.06,0,.11-.04c0,0-.01,0-.03,0t0,0s-.07,0-.08.05ZM160.52,9.48v-.06s-.06.02-.06.02h-.03s-.02.02-.04.02l.06.04.07-.02ZM160.57,9.23v.03s.06,0,.06-.02c0-.02,0-.06-.04-.11l-.09.11.07-.02ZM160.65,9.18s0-.03,0-.03c.02,0,.03,0,.03,0v-.03s.01-.02.02-.06h-.06s.02.06.02.06v.06ZM160.59,8.98l.06-.12v-.03s-.02,0-.02,0l-.06.12v.03s.03,0,.03,0ZM160.78,9.02s0-.04.01-.06c.03-.04.07-.07.12-.1l-.04-.11h-.03s-.02.09-.02.09v.03s-.05.05-.06.09c0,.02-.02.04-.04.06v.03s.06-.02.06-.02ZM160.98,8.7s-.01-.05.01-.06c.05-.01.07-.03.08-.05v-.06s-.06.02-.06.02l-.05.09-.08.05.09.02ZM161.27,8.27s.02-.03.04-.02h-.06s0-.02-.03-.02c0,0,0,.01,0,.03l.02.07.04-.06ZM161.44,7.92c.05-.03.08-.07.09-.11l-.11.07s0,.03.03.04ZM161.58,7.91s.07,0,.07-.02c0-.02,0-.03-.02-.04l-.07.02s0,.03,0,.03c.02,0,.03,0,.03,0ZM161.94,7.43s.03-.07.05-.09h-.03s-.05.08-.05.08v.03s.03-.02.03-.02ZM162.39,6.55s.02-.02.08-.05l.2-.32v-.06s.02-.03.02-.03c-.03.02-.06.02-.1.01l-.04.02c.03.05.05.08.05.08,0,.02-.02.03-.04.02-.02,0-.03,0-.04.02-.02.1-.06.17-.11.21l-.02.09ZM162.57,5.57c.08-.05.11-.07.11-.07l-.06-.04s-.03.05-.08.08l.02.04ZM162.75,5.35s0-.03-.02-.04l-.04.06.02.07.05-.09ZM162.88,5.21l-.06-.04-.04.02s0,.01,0,.03c0,0,.01,0,.03,0l.07-.02ZM163.82,4.8l.11-.07-.06.12-.04.02-.02-.07ZM164.27,5.29s.03-.05.08-.08l-.02-.04s-.07,0-.08.05l.02.07ZM163.93,4.72c.01-.06,0-.09-.05-.08,0-.02.03-.05.08-.08h.03s.03-.02.07-.01c0,.04-.03.07-.05.09,0,.02-.03.05-.08.08ZM164.17,4.22l.09-.11.03.04-.12.1v-.03ZM174.04,28.28c.02-.1.05-.17.08-.21s.04-.09.03-.16c0-.07,0-.12.03-.16.03-.04.04-.09.03-.16,0-.04.03-.08.06-.12l.11-.5s0-.05-.01-.1c-.02-.03-.02-.05-.02-.07-.02-.03-.02-.07,0-.13.02-.08.02-.15.01-.19v-.06s.02-.04.03-.06c.03-.02.04-.05.05-.09v-.06s.02.13.02.13l-.05.09v.03s.02,0,.02,0c.08-.16.13-.29.15-.39v-.03s0-.05,0-.1c0-.04.02-.06.04-.06.05-.03.07-.08.07-.15-.01-.05-.01-.09,0-.13.02,0,.02,0,0-.03,0-.02,0-.03,0-.03.12-.13.13-.22.06-.28-.05-.08-.06-.13-.03-.17.05-.03.08-.05.08-.05l.16-.46c.08-.18.18-.41.28-.69l.15-.39s0-.01,0-.03c0,0,0,0-.03,0v.03c-.11.07-.16.1-.16.1v-.03s.02-.06.02-.06c-.05.03-.08.05-.08.05-.1.15-.16.3-.2.45v.06c-.15.23-.24.41-.29.53l-.27.5s-.05.05-.09.11c-.03.06-.05.1-.06.12l-.07.18c-.07.14-.16.33-.25.57l-.11.21v.03s0-.03,0-.03l.02-.09c.03-.15.09-.27.18-.39.02-.1.05-.17.08-.21.03-.15.07-.25.13-.3.03-.02.05-.08.07-.18l.24-.5c.02-.1.07-.24.15-.39v-.06s.03-.05.07-.09c.03-.04.04-.07.02-.09.03-.02.03-.04.01-.06-.02-.03-.03-.04-.03-.04v-.13c.03-.06.07-.13.11-.21.03-.06.06-.13.08-.21.04-.08.08-.21.12-.4l.15-.39.05-.22.05-.25c.02-.08.07-.22.16-.42v-.03s0,0-.02,0c0,0,0,.01,0,.03-.03.04-.06.08-.1.14-.03.04-.06.08-.1.14-.16.36-.31.62-.43.79l-.08.21s-.02.03-.04.02v-.03s.07-.12.07-.12c0,0-.01,0-.03,0,0,0,0-.01,0-.03v.03s-.11.17-.11.17c-.01.06-.05.13-.11.21-.04.08-.06.14-.07.18v.03s0-.03,0-.03l.07-.15s0-.06-.02-.07c0,0,0,0-.03,0,0,0,0,.01,0,.03l-.08.21s-.05.1-.07.18l-.16.29-.12.27c-.1.24-.18.43-.25.57v.03s0-.03,0-.03l.22-.71.11-.21c.01-.06.03-.13.04-.19.03-.06.05-.13.05-.22l.05-.22v-.03s0,.03,0,.03l-.16.29.09-.27s.02,0,0-.03v.03c-.04.06-.08.13-.12.21-.04.08-.09.16-.15.23,0,.02-.02.03-.04.02-.02,0-.03,0-.03,0v-.03c.04-.06.08-.13.12-.21.04-.08.06-.14.07-.18l.32-.75.12-.27s0-.02.01-.06c.03-.04.02-.06-.02-.07v-.06s.13-.24.13-.24c0-.04,0-.06-.02-.07v.03s-.06.09-.07.15l-.09.11s-.02.03-.04.02v-.03s.14-.3.14-.3v-.06s-.03.02-.03.02c0,.02-.02.03-.04.02l-.02.09.02-.09.46-1.05.11-.21v-.03s0,0-.02,0c0,0,0,.01,0,.03l-.19.45s-.03,0-.04.02v-.03s.01-.03.01-.03l.02-.09s-.04.05-.05.09l-.15.23s-.01,0-.03,0c0,0,0,.01,0,.03v-.06s.08-.15.08-.15l.13-.3v-.03s-.04.06-.04.06v-.06s.22-.48.22-.48c.2-.5.36-.92.5-1.24l.47-1.27.16-.46c.01-.06,0-.1-.04-.11-.2,0-.51-.02-.93-.07-.13-.03-.3-.04-.51-.05l-1.31-.15c-.38-.04-.68-.06-.87-.06-.04,0-.1.01-.18.06-.29.13-.59.34-.89.63l-.15.07c-.18.14-.5.38-.95.74-.29.24-.49.42-.61.52-.02.02-.12.1-.29.27l-.04.06c0,.09-.04.14-.13.17l-.13.14-.33.29s-.03.06-.08.05c-.08.05-.11.07-.11.07-.16.12-.38.36-.68.74-.02.02-.07.08-.14.2l-.04.06v-.06s.04-.13.04-.13l.35-.55.02-.09s0-.1.07-.15c.02,0,.03,0,.03,0,0-.02,0-.03,0-.03.06-.07.13-.19.21-.35.02-.02.05-.07.06-.15.02-.08.05-.14.1-.17l.66-.64.09-.11-.15.07s-.09.05-.12.1c-.05.05-.1.09-.12.1-.16.14-.29.23-.39.28l-.09.11-.08.08s-.07,0-.07.02l-.02-.04c.05-.03.08-.05.08-.05.02,0,.03,0,.03,0,0-.02,0-.03,0-.03.01-.06.09-.16.22-.28.11-.11.17-.18.18-.22.07-.12.1-.17.1-.17.02,0,.03,0,.03,0-.02-.03-.02-.04-.02-.04-.02,0-.03,0-.04.02-.09.11-.21.24-.38.38l-.04.06c-.07.12-.13.2-.19.25-.06.05-.18.17-.37.35,0,.02,0,.03,0,.03-.02,0-.03,0-.03,0v-.03s.1-.11.1-.11c.04-.17.15-.33.33-.48.16-.14.27-.26.34-.35.04-.1.1-.16.17-.19h.03s0-.07.05-.08c.02-.02.05-.03.08-.05l.06-.12c.05-.03.08-.06.08-.08v-.03s-.02,0-.02,0l-.11.07c-.07.1-.14.14-.23.15-.04,0-.09.03-.16.13l-.07.02.04-.06c.03-.06.11-.14.22-.25.1-.04.23-.19.39-.44l.04-.06.04-.06-.07.02c-.13.08-.45.34-.99.77l-.04.02v-.06s.53-.41.53-.41l.1-.17-.06-.04s-.06,0-.11.04c0,.02,0,.04-.01.06-.02,0-.04,0-.07.02l.03-.13c.05-.03.11-.09.17-.16.08-.05.09-.09.03-.13h-.03s-.07.01-.07.01l.04-.06c.06-.07.12-.13.16-.16l.22-.25.27-.2.47-.36.32-.26.12-.1v-.06s-.06-.06-.04-.08c.03-.02.05-.03.08-.05l.04-.02.04-.02v.06s-.02.03-.02.03h.03s.05-.03.08-.04c.05-.01.09-.02.14-.04l.09-.11v-.03s-.05-.04-.05-.04c0,.02-.03.04-.08.05l-.06.12s-.02,0-.06-.01v-.03c.14-.12.22-.19.25-.21.03-.04.07-.07.12-.1.05-.03.09-.07.12-.1.05-.01.1-.06.16-.13.11-.13.19-.21.22-.25l-.02-.04s-.01,0-.03,0c0,0,0-.01,0-.03v-.06s.08-.02.08-.02l.22-.25.22-.12.85-.73.39-.28.43-.33.04-.02v-.06s-.02,0-.02.02l-.43.33-.18.09s-.02.03-.04.02v-.06s.18-.16.18-.16c0-.02,0-.03,0-.03.02-.02.03-.04.01-.06v-.03c.09-.07.16-.14.22-.22.08-.09.17-.17.25-.24.39-.31.59-.46.59-.46l.37-.35c.2-.22.4-.39.6-.52l.62-.62c.08-.07.17-.15.28-.23.11-.09.23-.2.37-.35l.62-.59c.28-.27.43-.42.46-.46.1-.07.2-.15.29-.27.17-.18.31-.31.41-.37.08-.07.18-.16.29-.27.11-.11.23-.24.35-.38.07-.1.17-.19.32-.29.15-.1.27-.17.34-.22l.15-.07c.05-.03.12-.04.2-.02.08.02.15.02.19,0,.18,0,.28,0,.33,0,.08.02.18.06.3.13.04.03.11.06.21.08.04,0,.09.02.16.03.06.01.1.03.12.06.02.03.04.04.09.05.06.03.14.07.24.12.12.05.22.1.29.16.05.08.15.17.3.29l.2.14.07.15c.08.04.12.08.14.13.04.03.07.05.09.05l.08.08.14.39v.06s-.16.07-.16.07c-.1.07-.17.15-.22.25-.04.17-.08.31-.13.43-.05.12-.09.22-.13.3l-.2.61-.31.82-.23.61c-.13.41-.25.73-.34.97-.04.1-.09.21-.14.33-.04.1-.09.2-.13.3-.01.06-.04.12-.07.18-.03.04-.05.09-.07.15l-.1.17c-.09.11-.15.18-.17.19l-.04.06c-.09.11-.17.33-.24.67,0,.02.01.04.06.04l.09.02h-.1s-.02.04-.04.04c-.02,0-.03,0-.04.02,0,.04,0,.06.02.07.05-.01.07-.02.07-.02h.03s0,.04,0,.04l-.04.02.05.04s.11,0,.2,0h.06s-.03.02-.04.04h-.16s-.04.02-.04.02h.03s.37.12.37.12l.16.03s.04,0,.06.01c.04,0,.07.03.09.05.02.03.07.05.15.07l.41.06h.06s-.07.03-.07.03c-.13.01-.24.01-.33,0-.02,0-.03,0-.04.02h.03s.16.04.16.04l.02.04h-.03s-.1,0-.16,0l-.55-.02s0,.01,0,.03c0,0,0,0-.03,0h.03s.66.12.66.12c.12.03.22.04.29.03l.06.04h-.06s-.39-.03-.39-.03c-.02,0-.1.01-.24.05-.13.01-.25.01-.36-.01-.05.01-.11,0-.19,0v.03s.21.08.21.08c.02,0,.03,0,.04-.02.05-.03.1-.03.13,0,.04,0,.07.02.09.02.02,0,.03.02.02.04h-.03s-.02.02-.04.02h.03s.03.02.02.04v.03s.03,0,.03,0c0-.02,0-.03,0-.03l.07-.02.51.05c.12.03.22.04.29.03l.03.04h-.03s-.02.02-.04.02h.03s.48.08.48.08l.21.08s-.03,0-.04.02c-.08-.04-.15-.05-.22-.05-.04,0-.07-.02-.09-.02-.07,0-.17,0-.32-.04-.06-.01-.12,0-.17.03h-.03s-.06-.02-.06-.02c-.06-.01-.12-.01-.16,0-.05.01-.09.01-.13,0l-.07.02s.03.02.02.04c.02,0,.03.02.02.04h-.03s-.03-.01-.03-.01h-.06s-.02.08-.02.08h.06s.26,0,.26,0c.04.03.09.04.16.03.07,0,.11,0,.13,0,.02,0,.03,0,.03,0h.06s-.03.04-.07.03c-.18,0-.33,0-.45-.03l-.11.04s-.03,0-.04.02h.03s.41.09.41.09l.09.05h.03s.41.06.41.06c.17.04.28.05.35.04l.29.03.45.03h.06s.06.06.06.06h-.06s-.52-.03-.52-.03h-.33s-.07.01-.07.01h.06s.2.02.2.02c.19.04.43.07.73.09.1.02.24.03.42.03l.51.05c.12.03.22.04.29.03.04,0,.04.02,0,.03,0,0,0,.01,0,.03,0,0,0,0,.03,0,.02,0,.03,0,.04-.02l.69.12.99.12.25.05h.03s-.03.01-.04.03l-.26-.02h-.65s-.42-.04-.42-.04c-.08-.02-.16-.02-.22-.02-.28-.02-.49,0-.63.03h-.65s-.8-.09-.8-.09l-.68-.02-.65-.04-.55-.02-1.24-.04s-.1.02-.17.03c-.06-.01-.12-.01-.16,0-.04,0-.07,0-.08.05l-.14.36-.19.42c-.01.06-.05.11-.1.14,0,0-.01,0-.03,0,0,0,0,.01,0,.03v-.03s.09-.21.09-.21l.08-.21.05-.09.03-.13-.11.07v-.03s-.01-.07,0-.13v-.03s-.03.02-.03.02l-.07.18c-.04.1-.09.24-.13.43-.02.02-.04.03-.04.06.02,0,.04,0,.07-.02.02,0,.02.02,0,.03l-.08.05c-.06.05-.1.13-.15.23-.02.08-.03.15-.04.19-.08.35-.15.61-.23.77l-.4.96c-.04.1-.14.32-.3.65-.06.16-.12.31-.2.45-.07.12-.12.22-.17.32-.14.34-.28.63-.41.86-.14.23-.23.42-.29.56-.08.16-.12.28-.14.36,0,.04-.01.06-.01.06,0,.07-.02.14-.08.21l-.16.29-.24.37c-.01.06-.03.11-.06.15-.18.33-.27.51-.28.53-.03.02-.05.06-.06.12l-.06.12c-.09.22-.17.37-.23.44-.09.2-.14.35-.16.46l-.23.61c-.02.08-.05.16-.08.24-.04.08-.07.15-.08.21,0,.04-.05.11-.11.21-.05.12-.07.24-.07.34v.03s-.07,0-.08.02c0,.04-.02.07-.02.09-.06.07-.1.14-.11.21h-.03s0-.04,0-.04ZM168.85,17.34l.09-.11v-.03s-.03,0-.03.02c-.05.03-.08.06-.08.08v.03s.03,0,.03,0ZM174.63,25.56s-.03-.04-.01-.1l.06-.12h.03c-.01.07-.03.11-.06.13l-.02.09ZM174.3,22.84s0-.03,0-.03c.02,0,.03,0,.03,0,.02-.08.06-.16.12-.24v-.06s.02-.03.02-.03l-.04.02-.13.3v.03ZM174.52,23.05s.06,0,.11-.04c-.02,0-.03-.02-.02-.04,0-.02,0-.03,0-.03-.04,0-.07.02-.08.08v.03ZM174.82,23.8c.05-.03.08-.05.08-.05l.02-.09-.08.08v.06ZM174.67,22.82l.04-.06c.01-.06.04-.11.07-.15h.03s0,.04,0,.04c0-.02,0-.03,0-.03.02,0,.03,0,.03,0l.02-.23v-.03s-.03,0-.03.02c-.07.12-.11.22-.13.3-.03.02-.04.06-.06.12,0,0,0,.02-.01.06l.04-.06ZM174.7,22.04s0-.03-.02-.04v.03s-.05.07-.07.15c-.03.04-.05.09-.07.15l.16-.29ZM175.22,23s.05-.06.06-.12h.03c.02-.08.02-.14,0-.19v-.03s0,.03,0,.03l-.13.3h.03ZM174.95,22.26c.06-.07.1-.14.11-.21.04-.06.06-.11.07-.15l.02-.09v-.03s-.03,0-.03.02v.03c-.08.05-.12.11-.11.17l-.05.09c-.05.03-.08.08-.1.14l.02.07.08-.05ZM174.88,21.1s.04-.03.04-.06c0-.04.03-.07.05-.09v-.06s-.03.06-.03.06l-.04.06-.02.09v.03s0-.03,0-.03ZM175.24,21.67v-.03c.02-.06.04-.11.07-.15l-.03-.04v.03s-.1.11-.1.11c-.05.01-.06.03-.04.06.02.03.02.05.02.07h.03s.04-.05.04-.05ZM175.39,21.31l.04-.06c.02-.08.06-.18.13-.3v-.03s.01-.03.01-.03h-.03s-.19.41-.19.41l.02.04v-.03ZM175.14,20.5s.03,0,.04-.02l.05-.09.03-.13v-.06s-.03.06-.03.06c-.02.1-.05.18-.08.21v.03ZM172.22,14.14s.06,0,.07-.02c.03-.02.04-.03.04-.06.04,0,.07,0,.1-.01.03-.02.04-.03.04-.06.03-.04.08-.07.15-.1.07-.03.12-.06.15-.1.05-.03.08-.08.1-.14.02-.02.04-.05.05-.09h.03s0,.05-.01.07c.02,0,.03,0,.04-.02.05-.01.08-.05.09-.11.03-.06.06-.1.09-.11,0,0,0-.01,0-.03,0-.02,0-.03-.02-.04-.02,0-.04,0-.07.02,0,.02-.01,0-.03-.04v.06s-.05.07-.11.14c-.05.01-.09.04-.11.07-.03.04-.06.06-.08.08-.02,0-.04.01-.04.06.02,0,.03,0,.04-.02l.02.04s-.03.06-.08.05c-.04-.03-.08-.03-.13,0-.08.05-.11.07-.11.07.01.05,0,.09-.03.13-.03.04-.06.06-.08.08,0-.04,0-.08-.01-.1l-.13.17h.03ZM175.51,20.29s0-.03,0-.03c.02,0,.03,0,.03,0,.02-.08.06-.18.13-.3v-.06s0-.1,0-.1l-.05.09s-.02.05-.05.09c0,.02,0,.05.01.1l-.07.18v.03ZM175.69,20.68l.19-.42v-.03s.02-.06.02-.06l-.04.06-.07.15-.13.3v.03s.03-.02.03-.02ZM173.31,13.33s.03-.07.05-.09v-.06s-.02.02-.02.02c-.05.03-.08.07-.09.11l-.02.09.08-.08ZM175.97,19.96s0-.03,0-.03c.03-.02.04-.03.05-.06.07-.12.11-.21.12-.27.07-.12.11-.21.12-.27v-.03s0,.01,0,.03c0,0-.01,0-.03,0v.06s-.18.29-.18.29v.03s0-.03,0-.03l.05-.09-.02-.07v.03s-.06.09-.07.15c0,.04-.04.08-.09.11l-.02.09s.01.04.06.04ZM173.56,13.09c.09,0,.14-.03.15-.07v-.03s0-.03-.02-.04c-.1.07-.15.1-.15.1v.03s.02,0,.02,0ZM175.83,19.11l.06-.12.09-.27v-.03s-.03.02-.03.02l-.15.39v.03s.03-.02.03-.02ZM175.86,18.82c.08-.16.13-.28.14-.36v-.03s0,.03,0,.03l-.1.17-.07.15v.03s.03,0,.03,0ZM173.76,12.48v-.03c-.09.04-.15.09-.18.12v.03s.18-.12.18-.12ZM173.84,13.02v-.06s.1-.11.1-.11c0,0,0-.02.01-.06l-.13.14v.06s-.06.06-.06.06l.07-.02ZM176.04,18.57l.04-.02v-.06s.03-.06.03-.06c0,.02-.02.03-.04.02l-.06.12.02.07v-.06ZM176,18.3v-.06s.03-.06.03-.06c0-.02,0-.03,0-.03.02,0,.03,0,.03,0l-.02-.04s0,.01,0,.03c0,0-.01,0-.03,0l-.02.09v.06s.02,0,.02,0ZM176.14,18.75c.01-.06.04-.11.07-.15l.04-.02h.03s0-.02,0-.02l-.02-.04-.03-.04v.03s-.12.21-.12.21v.03s-.01.03-.01.03l.04-.02ZM173.84,12.43l.12-.1v-.03s-.02,0-.02,0l-.12.1v.03s.02,0,.02,0ZM174.04,12.86s.03-.05.08-.08l.02-.09c-.08.05-.11.07-.11.07,0,.04,0,.08.01.1ZM174.04,12.67s0,.03,0,.03c.02,0,.03,0,.04-.02l.15-.07-.02-.04s0-.02-.03,0l-.11.07v.03ZM175.09,15.12s.06-.02.1-.01h.06s.07,0,.07,0h-.06s-.06-.03-.06-.03c-.06-.01-.1,0-.11.04-.04-.03-.1-.05-.18-.07h-.06s.06.03.06.03l.19.04ZM176.34,18.4s.03,0,.04-.02v-.03s.01-.03.01-.03l-.02-.07s-.01,0-.04.02c0,0-.01,0-.04.02v.03s.02,0,.02,0l.04-.02v.03s-.01.03-.01.03v.03ZM176.49,18.76s.03,0,.03,0c0-.02,0-.03,0-.03.03-.04.05-.09.07-.15v-.03s-.03.02-.03.02l-.06.12v.06ZM174.25,12.62c.05-.03.08-.06.08-.08l.03-.13c-.05.03-.08.06-.08.08l-.03.13ZM174.52,12.44s.04-.02.11-.07c-.05-.06-.08-.09-.07-.11-.05.03-.08.05-.08.05-.03.02-.04.03-.05.06,0,.02,0,.04.02.07l.02.07.04-.06ZM176.62,18.46s.02-.03.04-.02c.02,0,.03,0,.04-.02l.12-.24.04-.19-.02-.04v.03c-.03.1-.06.17-.09.21v.03c-.02.06-.05.12-.11.17v.06ZM176.62,17.74s0-.03-.02-.04l-.07.02.02.07.08-.05ZM174.67,12.35c.05-.03.08-.05.08-.05l-.02-.04s-.07,0-.07.02l.02.07ZM174.39,12.28l.17-.16.3-.2v-.03s-.02,0-.02,0l-.28.23-.2.15v.03s.03-.02.03-.02ZM174.79,12.24c.05-.03.08-.05.08-.05.05-.01.1-.07.16-.16l.13-.14.13-.14s.03,0,.04-.02h-.03s-.06.02-.11.04c-.05.01-.07.05-.06.12-.05.03-.09.05-.11.04-.02,0-.04,0-.07.02-.02.02-.04.03-.04.06-.02.08-.05.12-.09.11-.03.02-.04.05-.05.09l.02.04ZM175.1,11.42l.08-.05s-.03-.02-.02-.04l-.12.1v.03s.07-.05.07-.05ZM175.26,11.59l.16-.13v-.03s-.02,0-.02,0l-.13.17s-.09,0-.14.04c-.05.03-.08.07-.09.11h.03s.2-.15.2-.15ZM175.47,11.67l.13-.17v-.03s-.02,0-.02,0l-.16.13-.03.13.08-.05ZM175.37,14.26s.03.02.03.04c.02,0,.04,0,.07-.02l.74.06.69.15c.07-.03.11-.05.11-.07l.02-.09.23-.74.13-.43c.03-.06.06-.13.08-.21l.03-.13c-.05.03-.08.05-.08.05v.03s-.87.66-.87.66c-.1.07-.17.1-.22.12-.07,0-.15.04-.25.11l-.21.22c-.06.07-.11.13-.16.16-.06-.03-.11-.04-.16,0-.02.02-.06.03-.11.04,0,.04-.02.06-.05.06ZM175.9,11.34s.03,0,.03,0c0-.02,0-.03,0-.03.05-.03.08-.06.08-.08.05-.03.11-.09.17-.16v-.06s.03-.06.03-.06l-.04.06-.04.06s-.05.04-.08.08c0,.02-.03.03-.07.02v.03s-.03.07-.06.09v.03s-.01.03-.01.03ZM177.49,14.46s.07-.03.08-.05l.03-.16.04-.06s-.06.02-.1.01l-.06.12v.06s0,.07,0,.07ZM177.38,14.34l.23-.44s0-.03-.02-.04v.03s-.12.24-.12.24c-.02.08-.04.15-.08.21v.03s0-.03,0-.03ZM176.31,10.96l.12-.1-.02-.07h-.03s-.04.06-.1.14v.06s.02-.02.02-.02ZM177.62,14.46s.04-.01.04-.06c.04-.08.07-.18.1-.31v-.06s-.02.02-.02.02l-.12.4-.02.09.02-.09ZM177.62,14.16l.09-.11-.02-.07-.05.06s-.07.04-.08.08v.03s.06.01.06.01ZM177.85,14.6s.06,0,.07-.02c.02,0,.02,0,0-.03,0-.02,0-.03,0-.03-.04-.03-.02-.08.03-.16,0-.02.01-.02.03,0h.03s0-.03-.02-.03c-.03-.07-.02-.12.03-.16v-.06s-.01-.04-.01-.04v.03s-.05.05-.06.09c0,.02-.02.04-.04.06l-.06.28v.06ZM178.29,13.62s.01-.06.01-.06c0-.02-.01-.04-.06-.04,0-.02,0-.02-.03,0l.06.04.02.07v.06s0-.06,0-.06ZM178.69,14.52l.06-.12v-.06s-.06.05-.06.05c0,.02-.02.04-.04.06,0,.02,0,.04.02.07,0,.04,0,.06.02.07v-.06ZM178.08,12.95s.03-.03,0-.03l.13-.3s-.01,0-.03,0c0,0,0-.01,0-.03v.03c-.04.06-.07.15-.1.27v.06ZM178.63,13.86l.04-.06s0-.03-.02-.04c0-.02,0-.04.01-.06v.06s-.06.05-.07.09l.02.07v-.06ZM180.17,14.19s0-.03,0-.03c.02,0,.03,0,.03,0,.09-.11.14-.19.15-.23l.13-.59v-.03s0,.03,0,.03l-.25.7-.06.12v.03ZM182.28,16.38c.09-.02.16-.03.2-.02.02-.02.04-.01.03,0,.02,0,.04,0,.06.01l.06.04h-.06c-.08-.03-.15-.03-.2-.02l-.09-.02ZM183.26,26.38c-.19-.13-.34-.21-.43-.26-.07-.06-.16-.12-.25-.19-.08-.06-.15-.12-.22-.18-.19-.13-.32-.24-.38-.34-.19-.13-.35-.29-.48-.5-.13-.11-.2-.28-.22-.51.02-.08.02-.16.02-.23,0-.07-.02-.12-.03-.17l.08-.67c0-.09.02-.25.07-.48l.16-.75c.06-.18.14-.48.23-.9l.13-.59.09-.27.03-.16c.04-.1.09-.25.13-.46.02-.1.05-.23.08-.38.06-.16.13-.34.22-.54l.21-.81c.05-.14.11-.35.17-.62.05-.14.11-.36.17-.65.04-.1.09-.24.13-.43l.17-.62.17-.62.14-.49.15-.56c.03-.13.06-.24.11-.34.05-.12.09-.24.11-.37.01-.15.03-.28.05-.38.05-.12.08-.22.1-.31.05-.14.12-.38.19-.71l.25-.86.14-.49c.04-.21.09-.36.13-.46,0-.04.01-.11,0-.19.02-.1.05-.19.09-.24,0,0,0-.02-.02-.07,0-.04.03-.05.07-.02l.06-.12s0-.03-.02-.04c.05-.01.08-.05.09-.11.03-.06.05-.1.06-.12v-.03s0,.03,0,.03c.01.05,0,.12-.02.23v.03s.02,0,.02,0c0-.02,0-.03,0-.03l.03-.16v-.03s.04.02.03.04l-.06.28-.09.11s-.03.07-.05.09l.02.07s.02-.06.04-.06c0-.02,0-.03,0-.03.02,0,.03,0,.03,0l.06.04-.04.19c0,.09-.01.17-.05.25-.02.08-.02.17-.02.26l-.06.15v.03s.01.07,0,.13l-.09.24-.02.09c-.01.06-.01.11,0,.13-.03.04-.05.09-.07.15,0,.07,0,.12-.03.16,0,.02-.02.05-.05.09,0,.02,0,.06,0,.13,0,.04-.03.1-.07.18-.04.06-.04.11,0,.16.02,0,.03.02.03.04-.09.09-.12.17-.12.24.03.05.06.08.08.08l.04-.06c0-.13.02-.24.04-.32.04-.08.06-.14.07-.18,0-.07,0-.12,0-.16.03-.06.06-.11.06-.15l-.02-.07v-.03s.06-.09.07-.15c.02-.08.04-.14.07-.18.01-.06.02-.13,0-.19.01-.06.04-.13.08-.21v-.26s.04-.09.04-.09c.02-.1.05-.18.08-.21v-.03s.04,0,.04,0c.02.03.02.07,0,.13h.03s.03,0,.04-.02l-.02.09-.04.06h.03s.02.04.02.04c0-.02,0-.03,0-.03l.2-.45.04-.06s0,.03,0,.03c.02,0,.03,0,.03,0l-.02.09s-.05.04-.02.09v.06s-.06.06-.06.06v.03s.03,0,.03-.02c.1-.04.15-.12.15-.23.02-.1.04-.19.05-.25-.04-.03-.04-.07,0-.13.03-.06.06-.11.07-.15-.03-.05-.06-.08-.08-.08v-.03s.04,0,.04,0c.04,0,.06,0,.05-.06-.02,0-.03,0-.03,0,0-.02.02-.03.04-.02l.04-.06c.03-.06.07-.15.09-.27.02-.1.03-.19.02-.26l.15-.56v-.06s.03.07.03.07l-.07.31c-.03.06-.06.14-.09.24,0,.11,0,.19-.02.26l-.09.44c0,.13-.04.33-.1.6.02,0,.03.02.02.04v-.06s.06-.05.07-.09l-.02.09c0,.07,0,.15-.02.26v.06s-.03-.07-.03-.07v-.06s0-.03-.01-.04v.03s-.11.31-.11.31l.02.04s.05.06.04.14c0,.09-.01.2-.04.35-.03.13-.04.23-.04.32.02.03.01.05-.01.06,0,.02,0,.04-.01.06l.03.04.04-.02c.05-.25.1-.44.15-.56l.1-.47.07-.18s0-.04.01-.06c0-.04.03-.07.05-.09l.04-.02c-.06-.03-.08-.07-.07-.11.03-.04.05-.07.05-.09,0-.07,0-.12,0-.16.03-.04.05-.08.06-.12l.05-.22.03-.13s-.01-.1,0-.16c.03-.06.06-.11.07-.15v-.03s0,.03,0,.03v.36s0,.07,0,.07l.04-.06c.06-.05.1-.15.13-.3l.03-.29s0-.01,0-.03c0-.04.03-.06.08-.05.02,0,.04,0,.07-.02.02-.02.04-.03.04-.06.09-.2.12-.37.11-.5l.09-.11.02.04s.03.02.02.04c-.03.04-.05.1-.07.18,0,.02,0,.03,0,.03.02,0,.03,0,.03,0,.07-.03.11-.07.13-.14.03-.06.05-.1.06-.12l.08-.34s.02-.03.04-.02v.03s-.04.16-.04.16l.02.04.04-.02c.01-.06.03-.1.06-.12-.02,0-.03,0-.03,0,0-.02,0-.03,0-.03l.14-.2s.03,0,.03,0c0-.02,0-.03,0-.03.04,0,.06.02.05.04-.02.02-.04.05-.05.09.01.05,0,.08-.02.09l-.02.09s-.05.08-.06.12c.01.05,0,.08-.02.09-.06.1-.11.21-.14.33-.02.1-.04.18-.05.22l-.13.46s-.02.09-.03.16c0,.07,0,.14-.05.22l-.03.13s0,.06.04.11c0-.04.03-.07.05-.09l.24-.8c.06-.29.12-.5.17-.62l.07-.31c.01-.06.04-.12.07-.18.04-.08.07-.14.1-.17.04-.08.1-.16.19-.25.09-.09.15-.17.18-.22.13-.21.22-.35.25-.4l.04-.06-.04.06v.1c.06-.03.09-.05.09-.05.03-.02.05-.03.08-.05.03-.02.04-.03.04-.06,0-.02,0-.03,0-.03.02,0,.03,0,.03,0v.03s-.1.14-.1.14c-.04.1-.1.23-.18.39-.07.14-.14.31-.21.51-.08.16-.15.34-.21.54-.07.2-.11.35-.13.43l-.03.13c-.03.15-.07.26-.11.34-.05.23-.1.4-.15.52-.02.08-.04.18-.06.28,0,.11-.03.23-.08.38l-.09.73-.1.47c-.02.08-.03.2-.04.35,0,.13-.03.24-.07.34-.01.15-.04.28-.08.38-.02.1-.04.2-.06.28,0,.07-.01.15-.05.25-.02.1-.04.19-.05.25l-.17.78-.11.5c-.06.16-.11.36-.16.59-.03.23-.05.4-.08.51l-.2.78c-.03.15-.08.32-.15.52-.04.21-.09.45-.12.73-.04.1-.08.23-.12.4-.01.15-.02.26-.04.32l-.23.77v.06s0,.07,0,.07l.04-.02s.1-.05.16-.13c.08-.07.18-.18.3-.33.06-.1.13-.18.19-.25.08-.07.15-.14.21-.22l.33-.32.7-.83c.08-.07.25-.25.51-.54.04-.06.13-.14.28-.23v-.06s.44-.46.44-.46c.04-.06.07-.11.1-.14.06-.05.1-.11.13-.17.14-.12.25-.23.33-.32.09-.11.18-.21.26-.3.06-.07.15-.18.26-.3.14-.14.26-.26.37-.35.06-.1.18-.23.35-.42l.3-.33c.11-.09.25-.24.43-.46-.03.04.12-.13.47-.49l.54-.51s0-.03,0-.03c.02,0,.03,0,.03,0,.02,0,.03.02.02.04l-.03.13s-.04.02-.04.02c.02,0,.03,0,.03,0,.02,0,.03,0,.03,0,0-.02,0-.03,0-.03v.03s-.02.06-.02.06l.07-.02.51-.54s0-.03,0-.03c.02,0,.03,0,.03,0v.03s-.07.07-.1.11c-.03.02-.04.05-.05.09-.05.03-.08.07-.09.11.03.07.01.15-.05.25v.03s.03,0,.03-.02c.02,0,.03,0,.03,0,0-.02,0-.03,0-.03l.05-.06v.06s-.02.03-.02.03l.04-.02.14-.2.19-.12s0-.02,0,0c.02,0,.03,0,.03,0v.06c-.11.04-.19.14-.27.27l-.44.69-.17.16v.03s-.02.06-.1.11c0,.04-.04.08-.09.11l-.04.06s-.02.03-.04.02l.06.04.11-.04.46-.62.18-.22s.02-.03.04-.02v.06s-.18.32-.18.32l-.42.6c-.11.09-.18.19-.23.31,0,.02-.02.03-.04.02v.06s.02.03.05.01c.04,0,.1-.03.16-.13.05-.05.11-.12.17-.19.08-.07.16-.15.25-.24.1-.15.21-.27.34-.35l.26-.3c.1-.07.17-.12.2-.15.02,0,.02,0,0-.03,0-.02.02-.03.04-.02,0-.04.04-.08.09-.11l.22-.12.15-.1.2-.19.4-.47.07-.02v.06s-.05.03-.06.06c0,.02-.03.04-.08.05,0,0-.01.02-.04.06,0,.02.01.04.06.04v.03s-.02.03-.04.02h.06s.03,0,.04-.01l.02.07s0,.03,0,.03c.03.05.02.12-.05.22v.03s0-.03,0-.03c.02,0,.03,0,.03,0,.12-.06.2-.1.22-.12.02,0,.04,0,.07-.02.05-.03.08-.06.08-.08.18-.14.33-.29.46-.46,0,0,.03-.02.08-.05.04,0,.11-.02.21-.08.08-.05.13-.06.17-.03.14-.06.26-.12.34-.19.09-.09.25-.2.49-.32.05-.03.11-.09.17-.16.02,0,.03,0,.03,0,0-.02,0-.03,0-.03v.03s-.1.14-.1.14c-.24.19-.4.34-.49.45-.16.14-.31.28-.45.43-.14.12-.28.25-.45.39-.18.22-.32.39-.43.5-.06.05-.12.13-.18.22-.06.07-.13.16-.22.25-.03.06-.1.15-.19.29-.07.12-.14.21-.22.28-.1.15-.21.29-.32.42-.09.11-.18.22-.27.33-.18.22-.3.39-.37.51l-.15.26c-.01.06-.05.11-.1.14-.1.15-.21.28-.34.38-.14.23-.26.4-.37.51l-.45.56c-.18.22-.35.43-.52.61-.15.17-.28.31-.39.44l-.55.73-.38.38-.43.46c-.19.26-.35.46-.49.58-.09.11-.18.21-.26.3-.09.09-.16.17-.22.25-.06.07-.13.16-.22.25-.06.1-.13.19-.19.29-.06.1-.18.21-.34.35-.11.13-.25.28-.4.47-.13.19-.28.4-.46.62-.15.19-.26.34-.33.45-.08.07-.18.18-.3.33-.46.6-.73.96-.82,1.07-.04.08-.09.15-.14.2-.06.05-.1.12-.14.2-.03.06-.09.15-.15.26s-.1.23-.11.34l-.02.09-.1.31s-.02.06-.04.06c-.06-.01-.13.04-.2.15v.06c-.1.11-.24.17-.41.18-.12-.03-.21,0-.25.08-.06.05-.11.07-.18.06-.06-.01-.1-.02-.12-.03h-.06ZM183.05,17.95s0-.04.01-.06c.03-.02.03-.04.01-.06l-.06.12v.06s.03-.06.03-.06ZM183.23,18.19v-.03s.02-.06.02-.06l-.05.06s0,.01,0,.03c0,0-.01,0-.03,0,.02.03.02.06.01.1h.03s.02-.09.02-.09ZM183.3,18.01s-.02-.05-.02-.07l.04-.06c-.05.03-.08.06-.08.08-.02-.03-.03-.03-.03,0,.02.03.03.04.03.04h.06ZM183.44,16.47s.02-.03.04-.02c-.02-.03-.02-.06-.01-.1-.02,0-.03,0-.04.02,0,.04,0,.08.01.1ZM183.57,16s.03,0,.04-.02h.03s-.06-.04-.06-.04c0,0-.01,0-.03,0,0,0,0,.01,0,.03l-.02.09.04-.06ZM184.14,16.68l-.03-.04-.04.02-.04.06.02.07.09-.11ZM183.81,15.96l.03-.13s-.01,0-.03,0c0,0,0-.01,0-.03v.06s-.05.01-.06.06v.1s.06-.06.06-.06ZM183.68,15.5v-.06s-.02,0-.03.02c-.02.02-.03.06-.03.13l.05-.09ZM183.7,15.38c.02-.08.04-.15.08-.21,0,0-.01,0-.03,0,0,0,0-.01,0-.03,0,.02-.02.03-.04.02v.03s-.05.19-.05.19h.03ZM184.6,16.23s0-.08-.01-.1l-.04.06s0,.08.01.1l.04-.06ZM183.81,14.91l.04-.02h.03s-.02-.06,0-.13c0-.02,0-.03-.02-.04v.03c-.02.06-.04.11-.07.15,0,.04,0,.08.01.1l.02-.09ZM183.98,15.31v-.03s.05-.19.05-.19l.02-.09h-.03s-.05.08-.05.08l-.05.22v.06s.06-.05.06-.05ZM184.13,14.91l-.02-.07h-.03s-.01,0-.03-.01c0,0,0,.01,0,.03l.02.07.07-.02ZM183.93,14.48c.02-.08.05-.13.1-.14l.04-.02s-.1,0-.18.06c0,.04,0,.08.01.1,0,0,0,.01,0,.03,0,0,.01,0,.03,0v-.03ZM184.1,14.77s.04-.01.04-.06l.04-.06-.04-.11s.03-.04.01-.06c0-.02.02-.04.04-.06.03-.02.03-.03,0-.03-.02,0-.03-.02-.02-.04-.05.01-.07.04-.08.08l.02.07s-.03.03,0,.03c.02,0,.03,0,.03,0,0,.02-.04.07-.1.14,0,.02,0,.03.02.04.02,0,.03.02.02.04ZM184.51,14.96s.03-.02.08-.05c-.02,0-.03,0-.03,0,0-.02,0-.03,0-.03,0,0-.03.02-.08.05l.02.04ZM184.08,13.95s.02,0,0,0c0-.02,0-.03,0-.03v-.03s.03-.13.03-.13c.06.03.09.02.11-.04l.02-.09s0-.03-.02-.04v.03s-.02.06-.02.06c0,.02-.02.04-.04.06-.02,0-.03,0-.04.02v-.03s.06-.09.07-.15l-.06-.04v.03s-.11.34-.11.34c-.01.06-.01.11,0,.13l.05-.09ZM184.31,14.1v-.13s0-.03,0-.03c.05-.03.06-.07.03-.13l.04-.06s.02-.03-.02-.04c-.02,0-.06.02-.11.07l.02.2h-.03s.01.09.01.09l.02.07.04-.06ZM184.17,13.51s.02-.03.04-.02c-.02-.03-.02-.06-.01-.1-.02,0-.03,0-.04.02,0,.04,0,.08.01.1ZM184.45,13.57l-.02-.07-.07.02c-.01.06-.01.12,0,.16l.09-.11ZM184.75,13.87s.07-.04.08-.08l-.02-.07h-.03s-.01.06-.01.06c0,.04-.03.07-.05.09v.03s0,.01-.01.03c.02,0,.03,0,.04-.02v-.03ZM184.22,13.29s.07,0,.08-.05c.06-.07.07-.14.04-.19-.02,0-.02-.04-.01-.1.05-.01.06-.03.04-.06,0-.04.01-.06.01-.06,0-.04,0-.06-.02-.07.03-.02.03-.03,0-.03,0-.02,0-.04.01-.06l-.04-.14-.04.06s.01.1,0,.16c-.01.06-.03.15-.05.25,0,.11-.02.19-.05.25,0,0,0,.01,0,.03,0,0,.01,0,.03,0ZM184.84,13.62l.04-.06v-.03s.04,0,.04,0v.03s.02.04.02.04c0-.02,0-.03,0-.03,0-.04,0-.08-.01-.1-.02-.03-.04-.04-.09-.05l-.02.09v.06s-.02.03-.02.03h.03ZM184.39,13.43s.02-.03.04-.02c.04,0,.05,0,.04-.02,0-.04.02-.07.02-.09.05-.03.07-.08.06-.15.01-.06.02-.1.03-.13h.03s-.02-.05-.01-.09c.03-.15.06-.25.1-.31l-.02-.07s-.07,0-.07.02c-.03.02-.04.05-.05.09l-.07.34v.06s-.03.04-.06.06c0,.02-.01.05-.02.09.01.05,0,.1-.03.16l.02.07ZM184.39,12.48s.03,0,.04-.02v-.03s.02-.06.02-.06h-.06s.02.06.02.06v.03s-.01.03-.01.03ZM184.93,13.32l-.02-.04.11-.04v-.03s-.02-.04-.02-.04c-.08.05-.11.09-.09.11l-.04.02s-.02.06-.04.06l.05.04.05-.09ZM184.98,13.1l-.02-.04s.04-.05.05-.09l.08-.05-.06-.04s-.04.05-.05.09v.03s-.04.02-.04.02l.02.07h.03ZM185.11,12.83s0-.03-.02-.04c0-.02,0-.03-.02-.04,0-.02.02-.04.04-.06l.04-.06-.14.04.02.07s.03.02.02.04l.06.04ZM184.51,12.24l.02-.09s-.02-.06-.01-.1c0-.02,0-.04.01-.06.02-.02.03-.05.02-.09l.04-.02.03-.16s0,0-.03,0c0-.02.02-.04.04-.06.03-.04.04-.07.02-.09,0-.02,0-.04.01-.06-.02-.03-.02-.04-.02-.04.02-.02.04-.03.04-.06.05-.03.07-.05.04-.06-.05-.06-.05-.09.02-.09l.04-.02s0-.11,0-.19c0-.02,0-.04-.02-.07,0-.02.02-.04.04-.06l.02-.09-.11.04v.06c-.04.1-.07.23-.13.37-.03.13-.05.28-.07.48l-.02.09-.07.15-.03.16s0,.06.04.11l.04-.02ZM185.19,12.13l-.02-.07-.07.02s.02.06.01.1c0,.02,0,.04.02.07h.03s.03-.12.03-.12ZM184.98,12.21l.09-.41.07-.31-.02-.07c.08-.05.1-.1.07-.15,0-.02,0-.03-.03-.04l-.04.02s.01.1,0,.16c-.03.02-.04.06-.06.12v.26c-.02.13-.06.2-.11.24l-.03.13.02.07.04-.02ZM185.3,12.09v-.1s-.03-.04-.03-.04c.05-.03.07-.06.05-.09,0-.04.02-.07.02-.09l.05-.22s0-.04.01-.06c.03-.02.02-.04-.02-.07-.02,0-.03,0-.03,0,0-.02.02-.04.04-.06h-.03s-.07.01-.07.01c0,.02-.02.05-.05.09,0,.02.01.05.05.08,0,.02,0,.03,0,.03.02,0,.03,0,.03,0l-.04.02s-.07.04-.08.08c.02.03.02.04.02.04.03.07.03.14,0,.19v.06s.06.11.06.11h.03ZM184.8,10.77c.08-.05.11-.07.11-.07v-.06s.04-.13.04-.13t0,0s0-.03,0-.03h-.03c-.08.04-.12.12-.15.22.02,0,.03.03.02.07ZM184.9,10.43s-.02-.06-.01-.1c-.02,0-.03,0-.04.02l-.02.09.07-.02ZM185.26,10.9l-.06-.04v.03c-.02.08-.03.14,0,.16,0,.02,0,.03.02.04l.04-.19ZM185.02,10.33v-.03s-.01-.01-.05-.04c-.02,0-.03,0-.04.02,0,.04,0,.08.01.1,0,0,0,.01,0,.03.02,0,.04,0,.07-.02v-.06ZM188.6,16.66s.03,0,.03,0c.03-.02.05-.02.07-.02v-.03s-.09.01-.09.01v.03ZM185.44,11.27l.03-.16.12-.56.04-.19s0-.03-.02-.04c0,0-.01,0-.03,0,0,0,0,.01,0,.03.01.05,0,.09-.06.12-.02,0-.03,0-.04.02,0,.04-.02.09-.03.16,0,.04.01.08.07.11v.06s-.03,0-.05.02c0,0,0-.01,0-.03h-.03s0,.02,0,.02c-.03.06-.06.11-.06.15.01.05.02.08.01.1h-.03s.02.06.02.06c.02,0,.02.01,0,.03l-.02.09h.1ZM185.02,10.19s.03,0,.04-.02c.03-.06.07-.15.09-.27h-.03s-.06.05-.09.1c-.04.06-.06.11-.07.15l.06.04ZM188.96,16.35l-.06-.04-.04.02s-.04.08-.09.11l-.04.06v.03s.23-.18.23-.18ZM185.71,9.59c-.03-.05-.05-.08-.05-.08l-.02-.07h.03s.01.06.04.11v.03ZM190.17,14.84s.07,0,.08-.05l.04-.06s0-.03-.02-.04h-.03s-.04.05-.04.05l-.02.09ZM190.72,14.27s0-.03-.02-.04l-.12.1.02.04.12-.1ZM190.85,14.11v-.06s-.09.04-.09.04l.02.04.07-.02ZM191.33,13.59s.04-.07.1-.14c0,0-.01,0-.03,0,0,0,0-.01,0-.03,0,.02-.03.05-.08.08v.06s-.05.02-.05.02h.06ZM191.63,13.85s.01-.06.09-.11v-.03s-.02,0-.02,0l-.12.1s0,.02-.01.06l.07-.02ZM191.61,13.19s-.03,0-.03,0c0-.02,0-.03,0-.03-.05.03-.08.06-.08.08l.02.07.09-.11ZM192.11,12.54h.1s.04-.04.04-.04c0-.02,0-.03-.03-.04v-.03s.03-.09.03-.09h.03s-.03,0-.03,0l-.13.14-.04.02.02.04ZM195.06,32.82c.02-.1.05-.17.08-.21s.04-.09.03-.16c0-.07,0-.12.03-.16.03-.04.04-.09.03-.16,0-.04.03-.08.06-.12l.11-.5s0-.05-.01-.1c-.02-.03-.02-.05-.02-.07-.02-.03-.02-.07,0-.13.02-.08.02-.15,0-.19v-.06s.02-.04.03-.06c.03-.02.04-.05.05-.09v-.06s.02.13.02.13l-.05.09v.03s.02,0,.02,0c.08-.16.13-.29.15-.39v-.03s0-.05,0-.1c0-.04.02-.06.04-.06.05-.03.07-.08.07-.15-.01-.05-.01-.09,0-.13.02,0,.02,0,0-.03,0-.02,0-.03,0-.03.11-.13.14-.22.06-.28-.05-.08-.06-.13-.03-.17.05-.03.08-.05.08-.05l.16-.46c.08-.18.18-.41.28-.69l.15-.39s0-.01,0-.03c0,0,0,0-.03,0v.03c-.11.07-.16.1-.16.1v-.03s.02-.06.02-.06c-.05.03-.08.05-.08.05-.1.15-.16.3-.2.45v.06c-.15.23-.24.41-.29.53l-.27.5s-.05.05-.09.11c-.04.06-.05.1-.06.12l-.07.18c-.07.14-.16.33-.25.57l-.11.21v.03s0-.03,0-.03l.02-.09c.03-.15.09-.27.18-.39.02-.1.05-.17.08-.21.03-.15.08-.25.13-.3.03-.02.05-.08.07-.18l.24-.5c.02-.1.07-.24.15-.39v-.06s.04-.05.07-.09.04-.07.02-.09c.03-.02.03-.04.01-.06-.02-.03-.03-.04-.03-.04v-.13c.03-.06.07-.13.11-.21.03-.06.06-.13.08-.21.04-.08.08-.21.12-.4l.15-.39.05-.22.05-.25c.02-.08.07-.22.16-.42v-.03s0,0-.03,0c0,0,0,.01,0,.03-.03.04-.06.08-.1.14-.03.04-.06.08-.1.14-.17.36-.31.62-.43.79l-.08.21s-.02.03-.04.02v-.03s.07-.12.07-.12c0,0-.01,0-.03,0,0,0,0-.01,0-.03v.03s-.11.17-.11.17c-.01.06-.05.13-.11.21-.04.08-.06.14-.07.18v.03s0-.03,0-.03l.07-.15s0-.06-.02-.07c0,0-.01,0-.03,0,0,0,0,.01,0,.03l-.08.21s-.05.1-.07.18l-.16.29-.12.27c-.1.24-.18.43-.25.57v.03s0-.03,0-.03l.22-.71.11-.21c.01-.06.03-.13.04-.19.03-.06.05-.13.05-.22l.05-.22v-.03s0,.03,0,.03l-.16.29.09-.27s.02,0,0-.03v.03c-.04.06-.08.13-.12.21-.04.08-.09.16-.15.23,0,.02-.02.03-.04.02-.02,0-.03,0-.03,0v-.03c.04-.06.08-.13.12-.21s.06-.14.07-.18l.32-.75.12-.27s0-.02.01-.06c.03-.04.02-.06-.02-.07v-.06s.13-.24.13-.24c0-.04,0-.06-.02-.07v.03s-.06.09-.07.15l-.09.11s-.02.03-.04.02v-.03s.14-.3.14-.3v-.06s-.02.02-.02.02c0,.02-.02.03-.04.02l-.02.09.02-.09.46-1.05.11-.21v-.03s0,0-.02,0c0,0,0,.01,0,.03l-.2.45s-.03,0-.04.02v-.03s.01-.03.01-.03l.02-.09s-.04.05-.05.09l-.15.23s-.01,0-.03,0c0,0,0,.01,0,.03v-.06s.08-.15.08-.15l.13-.3v-.03s-.04.06-.04.06v-.06s.22-.48.22-.48c.2-.5.36-.92.5-1.24l.47-1.27.16-.46c.01-.06,0-.1-.04-.11-.2,0-.51-.02-.93-.07-.12-.03-.3-.04-.51-.05l-1.31-.15c-.38-.04-.67-.06-.87-.06-.04,0-.1.01-.18.06-.29.13-.59.34-.89.63l-.15.07c-.18.14-.5.38-.95.75-.29.24-.49.42-.6.52-.03.02-.12.1-.29.27l-.04.06c0,.09-.04.14-.13.17l-.13.14-.32.29s-.04.06-.08.05c-.08.05-.11.07-.11.07-.16.12-.38.36-.68.74-.03.02-.07.08-.14.2l-.04.06v-.06s.04-.13.04-.13l.35-.55.02-.09s0-.1.07-.15c.02,0,.03,0,.03,0,0-.02,0-.03,0-.03.06-.07.13-.19.21-.35.02-.02.05-.07.07-.15.02-.08.05-.14.1-.17l.66-.64.09-.11-.15.07s-.09.05-.12.1c-.05.05-.1.09-.12.1-.16.14-.29.23-.39.28l-.09.11-.08.08s-.07,0-.07.02l-.03-.04c.05-.03.08-.05.08-.05.02,0,.03,0,.03,0,0-.02,0-.03,0-.03.01-.06.09-.16.22-.28.11-.11.17-.18.18-.22.07-.12.1-.17.1-.17.02,0,.03,0,.03,0-.02-.03-.03-.04-.03-.04-.02,0-.03,0-.04.02-.09.11-.21.24-.38.38l-.05.06c-.07.12-.13.2-.19.25-.06.05-.18.17-.37.35,0,.02,0,.03,0,.03-.02,0-.03,0-.03,0v-.03s.1-.11.1-.11c.04-.17.15-.33.33-.48.16-.14.27-.26.34-.35.04-.1.1-.16.17-.19h.03s0-.07.05-.08c.03-.02.05-.03.08-.05l.06-.12c.05-.03.08-.06.08-.08v-.03s-.03,0-.03,0l-.11.07c-.06.1-.14.14-.23.15-.04,0-.1.03-.16.13l-.07.02.04-.06c.04-.06.11-.14.22-.25.1-.04.23-.19.39-.44l.04-.06.04-.06-.07.02c-.13.08-.45.34-.98.77l-.04.02v-.06s.53-.41.53-.41l.1-.17-.06-.04s-.06,0-.11.04c0,.02,0,.04-.01.06-.02,0-.04,0-.07.02l.03-.13c.05-.03.11-.09.17-.16.08-.05.09-.09.03-.13h-.03s-.07.01-.07.01l.04-.06c.06-.07.12-.13.17-.16l.22-.25.27-.2.47-.36.32-.26.12-.1v-.06s-.06-.06-.04-.08c.03-.02.05-.03.08-.05l.04-.02.04-.02v.06s-.02.03-.02.03h.03s.05-.03.08-.04c.05-.01.09-.02.14-.04l.09-.11v-.03s-.05-.04-.05-.04c0,.02-.03.04-.08.05l-.06.12s-.02,0-.06-.01v-.03c.14-.12.22-.19.25-.21.03-.04.07-.07.12-.1.05-.03.09-.07.12-.1.05-.01.1-.06.16-.13.11-.13.19-.21.22-.25l-.03-.04s0,0-.03,0c0,0,0-.01,0-.03v-.06s.08-.02.08-.02l.22-.25.22-.12.85-.73.39-.28.43-.33.04-.02v-.06s-.02,0-.02.02l-.43.33-.18.09s-.02.03-.04.02v-.06s.18-.16.18-.16c0-.02,0-.03,0-.03.03-.02.03-.04.01-.06v-.03c.09-.07.16-.14.22-.22.08-.09.17-.17.25-.24.39-.31.59-.46.59-.46l.37-.35c.2-.22.4-.39.6-.52l.62-.62c.08-.07.17-.15.28-.23.11-.09.23-.2.37-.35l.62-.59c.28-.27.43-.42.46-.46.1-.07.2-.15.29-.27.17-.18.31-.31.41-.37.08-.07.18-.16.29-.27.11-.11.22-.24.35-.38.06-.1.17-.19.32-.29.15-.1.27-.17.34-.22l.15-.07c.05-.03.12-.04.2-.02.08.02.15.02.19,0,.18,0,.28,0,.33,0,.08.02.18.06.3.13.04.03.11.06.21.08.04,0,.09.02.16.03.06.01.1.03.12.06.02.03.04.04.09.05.06.03.14.07.24.12.12.05.22.1.29.16.05.08.15.17.3.29l.2.14.07.15c.08.04.12.08.14.13.04.03.07.05.09.05l.08.08.14.39v.06s-.16.07-.16.07c-.1.07-.17.15-.22.25-.04.17-.08.31-.13.43s-.09.22-.13.3l-.2.61-.31.82-.23.61c-.13.41-.25.73-.34.97-.04.1-.09.21-.14.33-.04.1-.09.2-.13.3-.01.06-.04.12-.07.18-.03.04-.05.09-.07.15l-.1.17c-.09.11-.15.18-.17.19l-.04.06c-.09.11-.17.33-.24.67,0,.02.01.04.06.04l.09.02h-.1s-.02.04-.04.04c-.02,0-.03,0-.04.02,0,.04,0,.06.02.07.05-.01.07-.02.07-.02h.03s0,.04,0,.04l-.04.02.06.04s.11,0,.19,0h.06s-.03.02-.04.04h-.16s-.04.02-.04.02h.03s.37.12.37.12l.16.03s.04,0,.06.01c.04,0,.07.03.09.05.02.03.07.05.15.07l.41.06h.06s-.07.03-.07.03c-.14.01-.24.01-.33,0-.02,0-.03,0-.04.02h.03s.16.04.16.04l.02.04h-.03s-.1,0-.16,0l-.55-.02s0,.01,0,.03c0,0,0,0-.03,0h.03s.66.12.66.12c.12.03.22.04.29.03l.06.04h-.06s-.39-.03-.39-.03c-.02,0-.1.01-.24.05-.13.01-.25.01-.36-.01-.05.01-.11,0-.2,0v.03s.21.08.21.08c.02,0,.03,0,.04-.02.05-.03.09-.03.13,0,.04,0,.07.02.09.02.02,0,.03.02.02.04h-.03s-.02.02-.04.02h.03s.03.02.02.04v.03s.03,0,.03,0c0-.02,0-.03,0-.03l.07-.02.51.05c.12.03.22.04.29.03l.03.04h-.03s-.02.02-.04.02h.03s.48.08.48.08l.21.08s-.03,0-.04.02c-.08-.04-.15-.05-.22-.05-.04,0-.07-.02-.09-.02-.07,0-.17,0-.32-.04-.06-.01-.12,0-.17.03h-.03s-.06-.02-.06-.02c-.06-.01-.12-.01-.16,0-.05.01-.09.01-.13,0l-.07.02s.03.02.02.04c.02,0,.03.02.03.04h-.03s-.03-.01-.03-.01h-.06s-.02.08-.02.08h.06s.26,0,.26,0c.04.03.09.04.16.03.07,0,.11,0,.13,0s.03,0,.03,0h.06s-.03.04-.07.03c-.18,0-.33,0-.45-.03l-.11.04s-.03,0-.04.02h.03s.41.09.41.09l.09.05h.03s.41.06.41.06c.17.04.28.05.35.04l.29.03.45.03h.06s.06.06.06.06h-.06s-.52-.03-.52-.03h-.33s-.07.01-.07.01h.06s.19.02.19.02c.19.04.43.07.73.09.1.02.24.03.42.03l.51.05c.12.03.22.04.29.03.04,0,.04.02,0,.03,0,0,0,.01,0,.03,0,0,0,0,.03,0,.02,0,.03,0,.04-.02l.69.12.99.12.25.05h.03s-.03.01-.04.03l-.26-.02h-.65s-.42-.04-.42-.04c-.08-.02-.16-.02-.23-.02-.28-.02-.49,0-.63.03h-.65s-.8-.09-.8-.09l-.68-.02-.65-.04-.55-.02-1.24-.04s-.1.02-.17.03c-.06-.01-.12-.01-.16,0-.04,0-.07,0-.08.05l-.14.36-.19.42c-.01.06-.04.11-.1.14,0,0-.01,0-.03,0,0,0,0,.01,0,.03v-.03s.09-.21.09-.21l.08-.21.05-.09.03-.13-.11.07v-.03s-.01-.07,0-.13v-.03s-.03.02-.03.02l-.07.18c-.04.1-.09.24-.13.43-.03.02-.04.03-.05.06.02,0,.04,0,.07-.02.02,0,.02.01,0,.03l-.08.05c-.06.05-.1.13-.15.23-.02.08-.03.15-.04.19-.08.35-.15.61-.23.77l-.4.96c-.04.1-.15.32-.31.65-.06.16-.12.31-.2.45-.07.12-.12.22-.17.32-.14.34-.28.63-.41.86-.14.23-.23.42-.28.56-.08.16-.13.28-.14.36,0,.04-.01.06-.01.06,0,.07-.02.14-.08.21l-.16.29-.24.37c-.01.06-.03.11-.06.15-.18.33-.27.51-.28.53-.03.02-.05.06-.06.12l-.06.12c-.09.22-.17.37-.23.44-.09.2-.14.35-.16.46l-.23.61c-.02.08-.05.16-.08.24-.04.08-.07.15-.08.21,0,.04-.04.11-.11.21-.05.12-.07.24-.07.34v.03s-.07,0-.08.02c0,.04-.02.07-.02.09-.06.07-.1.14-.11.21h-.03s0-.04,0-.04ZM189.86,21.88l.09-.11v-.03s-.03,0-.03.02c-.05.03-.08.06-.08.08v.03s.02,0,.02,0ZM195.65,30.1s-.02-.04-.01-.1l.06-.12h.03c-.01.07-.03.11-.06.13l-.02.09ZM195.32,27.38s0-.03,0-.03c.02,0,.03,0,.03,0,.02-.08.06-.16.12-.24v-.06s.02-.03.02-.03l-.04.02-.13.3v.03ZM195.53,27.59s.06,0,.11-.04c-.02,0-.03-.02-.03-.04,0-.02,0-.03,0-.03-.04,0-.07.02-.08.08v.03ZM195.83,28.34c.05-.03.08-.05.08-.05l.02-.09-.08.08v.06ZM195.68,27.36l.04-.06c.01-.06.04-.11.07-.15h.03s0,.04,0,.04c0-.02,0-.03,0-.03.02,0,.03,0,.03,0l.02-.23v-.03s-.03,0-.03.02c-.07.12-.11.22-.13.3-.03.02-.04.06-.06.12,0,0,0,.02-.01.06l.04-.06ZM195.72,26.58s0-.03-.02-.04v.03s-.05.07-.07.15c-.03.04-.05.09-.07.15l.16-.29ZM196.23,27.54s.04-.06.06-.12h.03c.02-.08.02-.14,0-.19v-.03s0,.03,0,.03l-.13.3h.03ZM195.97,26.8c.06-.07.1-.14.11-.21.03-.06.06-.11.07-.15l.02-.09v-.03s-.03,0-.03.02v.03c-.08.05-.12.11-.11.17l-.05.09c-.05.03-.08.08-.1.14l.02.07.08-.05ZM195.89,25.64s.04-.03.04-.06c0-.04.03-.07.05-.09v-.06s-.03.06-.03.06l-.04.06-.02.09v.03s0-.03,0-.03ZM196.26,26.21v-.03c.02-.06.04-.11.07-.15l-.02-.04v.03s-.1.11-.1.11c-.05.01-.06.03-.04.06.02.03.02.05.02.07h.03s.04-.05.04-.05ZM196.4,25.85l.04-.06c.02-.08.06-.18.13-.3v-.03s.01-.03.01-.03h-.03s-.19.41-.19.41l.02.04v-.03ZM196.15,25.04s.03,0,.04-.02l.05-.09.03-.13v-.06s-.03.06-.03.06c-.02.1-.05.18-.08.21v.03ZM193.24,18.68s.07,0,.07-.02c.03-.02.04-.04.04-.06.04,0,.07,0,.1-.01.03-.02.04-.03.04-.06.03-.04.08-.07.15-.1.07-.03.12-.06.15-.1.05-.03.08-.08.1-.14.02-.02.04-.05.05-.09h.03s0,.05-.01.07c.02,0,.03,0,.04-.02.05-.01.08-.05.09-.11.03-.06.06-.1.09-.11,0,0,0-.01,0-.03,0-.02,0-.03-.02-.04-.02,0-.04,0-.07.02,0,.02-.01,0-.02-.04v.06s-.05.07-.11.14c-.05.01-.08.04-.11.07-.03.04-.06.06-.08.08-.02,0-.04.01-.04.06.02,0,.03,0,.04-.02l.03.04s-.04.06-.08.05c-.04-.03-.08-.03-.13,0-.08.05-.11.07-.11.07.01.05,0,.09-.03.13-.03.04-.06.06-.08.08,0-.04,0-.08-.01-.1l-.13.17h.03ZM196.52,24.83s0-.03,0-.03c.02,0,.03,0,.03,0,.02-.08.06-.18.13-.3v-.06s0-.1,0-.1l-.05.09s-.02.05-.05.09c0,.02,0,.05.01.1l-.07.18v.03ZM196.7,25.22l.19-.42v-.03s.02-.06.02-.06l-.04.06-.07.15-.13.3v.03s.03-.02.03-.02ZM194.33,17.87s.03-.07.05-.09v-.06s-.02.02-.02.02c-.05.03-.08.07-.09.11l-.02.09.08-.08ZM196.99,24.5s0-.03,0-.03c.03-.02.04-.03.05-.06.07-.12.11-.21.12-.27.07-.12.11-.21.12-.27v-.03s0,.01,0,.03c0,0-.01,0-.03,0v.06s-.17.29-.17.29v.03s0-.03,0-.03l.05-.09-.02-.07v.03s-.06.09-.07.15c0,.04-.04.08-.09.11l-.02.09s.01.04.06.04ZM194.58,17.63c.09,0,.14-.03.15-.07v-.03s0-.03-.02-.04c-.1.07-.15.1-.15.1v.03s.02,0,.02,0ZM196.84,23.65l.06-.12.09-.27v-.03s-.03.02-.03.02l-.15.39v.03s.03-.02.03-.02ZM196.87,23.36c.08-.16.13-.28.14-.36v-.03s0,.03,0,.03l-.1.17-.07.15v.03s.02,0,.02,0ZM194.77,17.02v-.03c-.09.04-.15.09-.18.12v.03s.18-.12.18-.12ZM194.85,17.56v-.06s.1-.11.1-.11c0,0,0-.02.01-.06l-.13.14v.06s-.06.06-.06.06l.07-.02ZM197.06,23.11l.04-.02v-.06s.03-.06.03-.06c0,.02-.02.03-.04.02l-.06.12.02.07v-.06ZM197.02,22.84v-.06s.03-.06.03-.06c0-.02,0-.03,0-.03.02,0,.03,0,.03,0l-.02-.04s0,.01,0,.03c0,0,0,0-.03,0l-.02.09v.06s.02,0,.02,0ZM197.15,23.29c.01-.06.04-.11.07-.15l.04-.02h.03s0-.02,0-.02l-.02-.04-.02-.04v.03s-.12.21-.12.21v.03s-.01.03-.01.03l.04-.02ZM194.85,16.97l.12-.1v-.03s-.02,0-.02,0l-.12.1v.03s.02,0,.02,0ZM195.05,17.4s.03-.05.08-.08l.02-.09c-.08.05-.11.07-.11.07,0,.04,0,.08.01.1ZM195.06,17.21s0,.03,0,.03c.02,0,.03,0,.04-.02l.15-.07-.02-.04s0-.02-.03,0l-.12.07v.03ZM196.1,19.66s.06-.02.1-.01h.06s.07,0,.07,0h-.06s-.06-.03-.06-.03c-.06-.01-.1,0-.11.04-.04-.03-.1-.05-.18-.07h-.06s.06.03.06.03l.19.04ZM197.36,22.94s.03,0,.04-.02v-.03s.01-.03.01-.03l-.02-.07s-.01,0-.04.02c0,0-.01,0-.04.02v.03s.02,0,.02,0l.04-.02v.03s-.01.03-.01.03v.03ZM197.51,23.3s.03,0,.03,0c0-.02,0-.03,0-.03.03-.04.05-.09.07-.15v-.03s-.03.02-.03.02l-.06.12v.06ZM195.27,17.15c.05-.03.08-.06.08-.08l.03-.13c-.05.03-.08.06-.08.08l-.03.13ZM195.53,16.98s.04-.02.11-.07c-.05-.06-.08-.09-.07-.11-.05.03-.08.05-.08.05-.03.02-.04.03-.04.06,0,.02,0,.04.02.07l.02.07.04-.06ZM197.64,23s.02-.03.04-.02.03,0,.04-.02l.12-.24.04-.19-.02-.04v.03c-.03.1-.06.17-.09.21v.03c-.02.06-.05.12-.11.17v.06ZM197.63,22.28s0-.03-.02-.04l-.07.02.02.07.08-.05ZM195.69,16.89c.05-.03.08-.05.08-.05l-.02-.04s-.07,0-.07.02l.02.07ZM195.41,16.82l.16-.16.3-.2v-.03s-.02,0-.02,0l-.28.23-.2.15v.03s.03-.02.03-.02ZM195.81,16.78c.05-.03.08-.05.08-.05.05-.01.1-.07.17-.16l.13-.14.13-.14s.03,0,.04-.02h-.03s-.06.02-.11.04c-.05.01-.06.05-.06.12-.05.03-.09.05-.11.04-.02,0-.04,0-.07.02-.03.02-.04.03-.05.06-.02.08-.05.12-.09.11-.03.02-.04.05-.05.09l.02.04ZM196.11,15.96l.08-.05s-.03-.02-.02-.04l-.12.1v.03s.07-.05.07-.05ZM196.28,16.13l.16-.13v-.03s-.02,0-.02,0l-.13.17s-.09,0-.14.04c-.05.03-.08.07-.09.11h.03s.2-.15.2-.15ZM196.49,16.21l.13-.17v-.03s-.02,0-.02,0l-.16.13-.03.13.08-.05ZM196.39,18.8s.03.02.02.04c.02,0,.04,0,.07-.02l.74.06.69.15c.07-.03.11-.05.11-.07l.02-.09.22-.74.13-.43c.04-.06.06-.13.08-.21l.03-.13c-.05.03-.08.05-.08.05v.03s-.87.66-.87.66c-.1.07-.17.1-.22.12-.07,0-.15.04-.25.11l-.21.22c-.06.07-.12.13-.17.16-.06-.03-.11-.04-.16,0-.03.02-.06.03-.11.04,0,.04-.02.06-.04.06ZM196.92,15.87s.03,0,.03,0c0-.02,0-.03,0-.03.05-.03.08-.06.08-.08.05-.03.11-.09.17-.16v-.06s.03-.06.03-.06l-.05.06-.04.06s-.05.04-.08.08c0,.02-.03.03-.07.02v.03s-.03.07-.06.09v.03s-.01.03-.01.03ZM198.5,19s.07-.03.08-.05l.03-.16.04-.06s-.06.02-.1.01l-.06.12v.06s0,.07,0,.07ZM198.4,18.88l.23-.44s0-.03-.03-.04v.03s-.12.24-.12.24c-.02.08-.04.15-.08.21v.03s0-.03,0-.03ZM197.33,15.5l.12-.1-.02-.07h-.03s-.04.06-.1.14v.06s.02-.02.02-.02ZM198.64,19s.04-.01.04-.06c.04-.08.07-.18.1-.31v-.06s-.02.02-.02.02l-.12.4-.02.09.02-.09ZM198.63,18.7l.09-.11-.02-.07-.05.06s-.07.04-.08.08v.03s.06.01.06.01ZM198.87,19.14s.07,0,.07-.02c.02,0,.02,0,0-.03,0-.02,0-.03,0-.03-.04-.03-.03-.08.03-.16,0-.02.02-.02.03,0h.03s0-.03-.02-.03c-.03-.07-.02-.12.03-.16v-.06s-.01-.04-.01-.04v.03s-.05.05-.06.09c0,.02-.02.04-.04.06l-.06.28v.06ZM199.31,18.16s.01-.06.01-.06c0-.02-.01-.04-.05-.04,0-.02,0-.02-.03,0l.06.04.02.07v.06s0-.06,0-.06ZM199.7,19.06l.06-.12v-.06s-.06.05-.06.05c0,.02-.02.04-.04.06,0,.02,0,.04.02.07,0,.04,0,.06.02.07v-.06ZM199.09,17.49s.03-.03,0-.03l.13-.3s0,0-.03,0c0,0,0-.01,0-.03v.03c-.04.06-.07.15-.1.27v.06ZM199.65,18.4l.04-.06s0-.03-.02-.04c0-.02,0-.04.01-.06v.06s-.06.05-.07.09l.02.07v-.06ZM201.18,18.73s0-.03,0-.03c.02,0,.03,0,.03,0,.09-.11.14-.19.15-.23l.13-.59v-.03s0,.03,0,.03l-.25.7-.06.12v.03ZM203.29,20.92c.09-.02.16-.03.2-.02.02-.02.04-.01.03,0,.02,0,.04,0,.06.01l.06.04h-.06c-.08-.03-.15-.03-.19-.02l-.09-.02ZM201.94,30.71c-.03-.05-.11-.11-.22-.18-.03.04-.06.03-.09-.02-.14-.07-.21-.15-.21-.24l-.05-.21-.04-.14v-.06s.02-.08,0-.1h-.03s0-.08-.03-.18c0-.02,0-.05-.01-.1,0-.02.02-.06.06-.12.03-.02.03-.08,0-.19-.01-.05-.04-.05-.09-.02v.03s-.04-.02-.03-.04c.03-.13.04-.22.03-.29,0-.02-.01-.06-.04-.11v-.06s.04.04.04.04h.03c.01-.06.01-.09-.01-.09-.02,0-.03-.02-.02-.04.01-.06.03-.1.06-.12,0-.02.01-.05.02-.09v-.03s-.03.02-.03.02v.06s-.04,0-.04,0c-.02-.03-.02-.07,0-.13-.01-.05,0-.08.02-.09,0-.02,0-.04.01-.06h.03c.05-.03.08-.05.08-.07,0-.02-.01-.06-.04-.11-.01-.05,0-.11,0-.19.02-.08.06-.17.12-.27.04-.1.07-.17.08-.21.03-.04.06-.08.1-.14.03-.06.08-.11.13-.17.07-.12.11-.18.11-.21v-.03s0,0-.02,0c0,0,0,.01,0,.03l-.14.2c-.06.07-.09.13-.1.17l-.07.02v-.06s.06-.1.12-.17c.01-.06.05-.13.11-.21.04-.08.08-.15.11-.21.03-.06.07-.12.1-.17l.15-.26s.02,0,0,0c0-.02,0-.03,0-.03v-.06s.06-.1.12-.17v-.03s-.03,0-.03,0l-.04.06-.04.02v-.03s0,0-.02,0c0,0,0-.01,0-.03v.03s-.14.17-.14.17l-.04.02v-.03c.02-.08.05-.14.08-.18.01-.06.03-.1.06-.12.03-.04.06-.07.09-.11l.04-.19h-.03s-.03,0-.04.02l-.07.02s-.01,0-.03,0c0-.02.02-.03.04-.02.02-.08.05-.13.1-.14v-.03c.05-.08.1-.17.16-.26.07-.1.11-.16.14-.2.06-.07.1-.13.1-.17.02-.02.03-.03,0-.03,0-.02,0-.04.01-.06-.04,0-.07,0-.07.02,0,0-.03.02-.08.05l.02-.09.09-.11v-.03s-.02,0-.02,0c0,.04-.04.08-.09.11v.03s0-.03-.03-.04l.06-.12v-.03s-.03,0-.03.02c-.05.03-.08.08-.1.14-.02,0-.03,0-.04.02h.06s0,.02,0,.04c0,0,.01,0,.03,0-.02,0-.03,0-.04.02-.06-.03-.1,0-.12.07l-.34.35v-.03s.15-.23.15-.23c.12-.17.24-.34.34-.52l.28-.4.04-.06s-.07,0-.07.02l-.13.17-.05.06s.02-.06.05-.06l.42-.6c.15-.17.35-.44.6-.82l.32-.42c.09-.13.2-.27.32-.42.12-.17.24-.35.35-.55.05-.12.1-.22.16-.29.06-.07.11-.14.14-.2.19-.26.32-.47.39-.6l.45-.72.34-.52c.14-.23.23-.41.28-.53l.13-.14c.19-.29.35-.54.46-.75.04-.08.12-.19.24-.34l.47-.98.32-.42.15-.26.13-.17.08-.05c.01-.06.05-.15.12-.27l.25-.24s.04-.05.05-.09c.05-.03.09-.05.11-.04.06.01.14,0,.23-.02v-.03c.04-.06.07-.14.09-.24.01-.06.08-.1.19-.12.04,0,.07,0,.1-.01.02-.02.05-.03.08-.05,0-.02.03-.05.08-.08,0-.02.02-.03.04-.02l.02-.09.07-.02-.04.02.02.07s.03,0,.03,0c0-.02,0-.03,0-.03.04,0,.06.02.06.04h.03s.03.01.03.01v.03s-.13.14-.13.14l-.02.09.04-.06s.06-.04.18-.06c.02,0,.06.01.12.03.09,0,.16-.03.21-.08l.04-.02.02.07s0,.08.01.1c.05-.03.08-.05.08-.05.02-.02.12-.1.29-.27.09-.02.15-.05.18-.09,0,0,0,0,.03,0,.02,0,.03.02.02.04,0,.07.06.09.15.07,0-.02.02-.03.04-.02l-.04.06s-.02.04-.04.06c-.03.02-.03.04-.01.06.02.03.06.04.12.06.08.02.12-.02.12-.1,0-.04.04-.06.08-.05.06.01.12,0,.17-.03.05-.01.1-.01.16,0,.06.01.11.04.15.07,0,0,.02.03.05.08.01.05-.01.1-.07.15-.03.04-.05.07-.05.09,0,.04,0,.06.02.07v.03s-.15.07-.15.07v.06c.07.11.09.27.04.5l-.06.25c-.04.17-.13.39-.27.66-.05.14-.11.36-.17.65l-.04.19c-.05.25-.08.53-.08.83.01.16,0,.4-.03.75,0,.09-.01.17-.05.25-.02.08-.03.17-.02.26-.02.1-.04.27-.04.48-.04.3-.07.67-.08,1.13l-.06.87-.05.68c-.02.3-.05.53-.09.7-.03.34-.06.6-.1.76,0,.02,0,.03.02.04-.03.13-.04.3-.05.51l.03.17c.03.07.03.25.02.53,0,.04-.02.1-.04.19,0,.07-.02.13-.07.18l.02.07.07-.02.24-.34.32-.42.26-.3.18-.22.29-.3.22-.28.15-.23s.11-.14.23-.31l.42-.56c.03-.06.07-.11.1-.14.04-.06.07-.11.1-.14l.19-.25.47-.65.21-.35.42-.56.37-.51.43-.63.59-.76c.06-.1.13-.18.19-.25.08-.07.14-.13.17-.19.12-.13.27-.32.46-.59l.42-.56.11-.07-.05.09-.24.37-.04.06c-.07.03-.15.12-.22.28,0,.02-.04.07-.1.14-.04.08-.12.19-.24.34-.06.07-.12.13-.17.16,0,0,0,.01,0,.03,0,0,0,0,.03,0h.03s.11-.2.11-.2l-.03.13-.02.09s-.04.03-.05.06c.02.03.05.03.09.02.05-.01.06.01.05.08-.02-.03-.04-.03-.06-.01-.02.02-.04.02-.04.02v.06s.01.04.01.04c.08-.05.11-.09.09-.11.09-.02.14-.08.13-.17,0,0,0-.01-.02-.04,0-.04.03-.06.08-.05.01-.06.04-.09.08-.08.02,0,.04-.01.04-.06-.03-.05-.02-.07.04-.06v-.03s-.02-.04-.02-.04c.03-.02.04-.03.04-.06l.2-.32.13-.17s.08-.08.17-.19l.04-.06.09.05h.03s.03-.03.01-.06h-.03s-.1,0-.1,0l.1-.14.07-.02h.03c.01.05.04.06.09.03l.13-.14s.02-.06.04-.06l.04-.06v.06s-.21.32-.21.32l-.04.06c-.05.03-.07.06-.05.09-.02.02-.04.05-.05.09.02.03.01.05-.01.06v.03s-.02,0-.04,0c0,0,0-.01,0-.03v-.03s.01-.03.01-.03v.03s-.1.11-.1.11c-.05.03-.05.07.01.1v.06c-.07.07-.11.14-.12.21,0,0-.01.02-.04.06,0,.02.01.04.06.04l-.02.09s-.03,0-.04.02h.06s.13-.12.13-.12c.08-.07.18-.2.31-.39l.15-.23s0-.03,0-.03c.02,0,.03,0,.03,0v.03c-.12.13-.21.26-.26.4v.03s.03,0,.03-.02l.19-.29s.1-.12.22-.25c0-.02,0-.03,0-.03.03-.02.03-.04.01-.06,0-.02.02-.03.04-.02.03-.02.04-.05.05-.09l.02.04s-.04.03-.04.06c.02.03.01.05-.01.06-.02.02-.05.09-.08.21l.07-.02.14-.2c.05-.03.1-.04.14-.04l.07-.02.04-.06-.04.02-.07.02s.02-.06.04-.06c0-.02.03-.05.08-.08h.03s.1-.14.1-.14c.02,0,.03,0,.03,0,0-.02,0-.03,0-.03.08.02.14-.04.17-.16,0-.02.02-.03.04-.02.05-.01.08,0,.09.02.07.06.13.08.18.07h.06s-.02.04-.04.04l-.31.23-.23.31s-.03,0-.04.02c.02,0,.03,0,.04-.02.05-.01.1-.06.16-.13l.13-.14c.04-.08.13-.14.27-.17.05-.01.1-.05.16-.13l.11-.07h.06s-.02.11-.02.11l-.04.02h.03s.07,0,.08-.04c-.02-.03-.01-.04,0-.03.02-.02.05-.02.07-.02.06.01.13-.03.19-.12,0,0,.1-.07.3-.2v.03s-.18.19-.18.19c-.04.06-.05.12-.04.19.03.05.06.08.08.08.06.01.07.04.02.07l-.08.08c-.2.13-.38.31-.54.54-.24.32-.45.65-.6.98-.07.1-.13.2-.2.32-.05.12-.1.23-.17.32-.14.25-.32.53-.54.83-.07.14-.2.34-.39.6-.03.06-.1.16-.2.32-.07.14-.17.26-.28.37l-.07.15-.45.72-.32.55c-.17.29-.29.47-.35.55-.05.12-.13.24-.24.37-.13.21-.3.43-.5.65-.09.2-.16.34-.22.41l-.04.06-.19.29-.38.7-.32.55c-.03.06-.07.11-.1.14-.03.02-.05.03-.08.05,0,.04-.03.07-.05.09,0,.02-.04.07-.1.14-.22.3-.38.51-.49.61l-.13.17s-.02.06-.04.06l-.46.59c-.19.18-.32.38-.39.6l-.19.25-.3.49c-.09.09-.16.19-.23.31-.04.1-.1.19-.15.26-.06.05-.1.16-.14.33-.02.08.01.14.09.18.06.03.08.07.07.11.01.05,0,.09-.03.13l-.15.26-.09.24c-.02.08-.06.13-.13.14l-.28.07-.07.02c-.06.07-.14.11-.25.11-.09,0-.14,0-.16,0l-.24.05s-.11-.01-.2,0c-.09.02-.17.02-.22-.02l-.52-.18-.17-.13c-.31-.2-.52-.35-.65-.47-.06-.03-.1-.08-.14-.13-.01-.05-.04-.08-.07-.11-.11-.2-.21-.46-.29-.78-.07-.26-.13-.61-.17-1.05l-.09-.77.02-.55c-.01-.13-.01-.25.01-.36,0-.18.01-.46.05-.84,0-.13.02-.31.05-.55.03-.23.06-.44.1-.63,0-.11.01-.2.03-.29.04-.1.07-.2.07-.31l.1-.47c0-.22.02-.38.04-.48l.11-.83c.04-.17.06-.4.09-.7.03-.15.06-.37.08-.67.01-.06,0-.12-.03-.17l-.09.11c-.12.15-.2.26-.24.34-.02.08-.06.17-.12.27-.06.07-.1.13-.13.17l-.24.34c-.09.11-.18.22-.27.33-.09.11-.17.22-.23.31-.22.32-.36.51-.42.56-.04.06-.11.14-.22.25-.01.06-.03.1-.06.12,0,.04-.09.15-.23.31,0,.04-.09.15-.23.31l-.55.73-.49.61-.48.71-.29.46c-.12.17-.2.27-.23.31l-.15.23c-.06.05-.12.14-.19.25-.04.08-.08.17-.12.27-.04.08-.09.16-.15.23-.18.33-.3.64-.37.94l-.1.47-.09.41c-.02.19.02.45.13.78,0,.02,0,.03.02.04.02.03.02.05.02.07.02.03.02.06.01.1-.04,0-.06-.02-.06-.04-.02-.03-.05-.02-.1.01-.06.05-.11.04-.16-.03l-.13-.16ZM200.91,29.27s-.03-.02-.02-.04l.06-.28.02.07-.05.22s.02.04.02.04c-.02,0-.03,0-.03,0ZM201.03,29.3s-.03-.02-.02-.04l-.04-.11.05-.09h.03c.01.05,0,.12,0,.2v.03ZM201.04,28.98s-.04-.05-.09-.02l.06-.12s.02-.03.04-.02c0,.02,0,.03,0,.03l.04.14s-.02.03-.04.02v-.03ZM200.86,28.12l.11-.21v-.03s0,.03,0,.03c-.02.1-.05.17-.08.21h-.03ZM201.3,28.67s.03,0,.04-.02c.02-.02.04-.06.06-.12v-.03s-.03,0-.03.02c-.02.02-.04.06-.06.12v.03ZM202.13,26.49l-.05-.08-.1.14h.03s.11-.07.11-.07ZM201.7,24.99c.09-.11.15-.18.17-.19v-.03s0,.03,0,.03l-.15.23s-.03,0-.04.02v-.06ZM202.41,25.67c.11-.09.18-.22.22-.41h-.03s-.06.07-.09.1c-.02.02-.04.06-.06.12-.02.08-.04.14-.07.18v.03s.03-.02.03-.02ZM203.77,24.82s.03,0,.04-.02l.09-.11v-.03s-.02,0-.02,0c0,.02-.04.07-.1.14v.03ZM204.98,23.28h-.03s-.13.13-.13.13v.03s.03,0,.03,0l.13-.17ZM204.39,22.4c.06-.07.09-.12.1-.14v-.03s-.13.17-.13.17h.03ZM205.08,23.14s.03,0,.04-.02l.04-.02c.19-.26.34-.46.45-.59,0-.02.02-.06.06-.12.03-.06.06-.1.09-.11l.3-.46.22-.28v-.03s-.03,0-.03.02l-.17.19-.02.09s-.03.02-.08.05c-.31.41-.53.73-.66.94l-.23.31v.03ZM208.29,25.86v-.1s-.06.06-.06.06v.1s.06-.06.06-.06ZM208.68,24.83l-.04-.11s0-.03-.02-.04v.03s0,.13,0,.13c.02,0,.03.02.02.04l.04-.06ZM206.52,21.19l.1-.17v-.03s-.13.17-.13.17v.03s.02,0,.02,0ZM208.6,24.55l.05-.06v-.03s0,0-.03,0c0,0,0,.01,0,.03l-.04.02c.03.05.05.08.05.08l-.03-.04ZM209.23,23.64l.02-.09h-.03s-.03-.01-.03-.01l-.06.12h.03s.07-.01.07-.01ZM208.84,22.84l.03-.13-.03-.04v.03s-.05.05-.06.09v.03s.02,0,.02,0h.03ZM208.66,21.59l.02-.09v-.03s-.02,0-.02,0c-.01.06-.03.1-.06.12,0,.02.01.04.06.04v-.03ZM209.38,21.58l.04-.02v-.03s-.06-.01-.06-.01c0,0-.01,0-.03,0,0,0,0,.01,0,.03.02.03.02.06.01.1l.04-.06ZM209.41,21.13s0-.03,0-.03c.02,0,.03,0,.03,0l.04-.06s-.03-.03-.02-.07h-.03s.02.06.02.06c0,.02-.02.03-.04.02v.06ZM213.08,23.85l-.11.07.02.04.09-.11ZM209.39,17.26s0-.03,0-.03c.02,0,.03,0,.03,0v-.1s-.06.06-.06.06l.02.07ZM213.12,23.37c.04-.06.08-.09.15-.1l-.02-.04h-.03s-.12.07-.12.07c0,0,0,.01,0,.03,0,0-.01,0-.03,0l.06.04ZM213.31,23.38c.08.02.12-.02.12-.1v-.03s-.01-.07-.01-.07l-.04.06s0,.05-.05.09l-.04.06h.03ZM213.53,22.8l-.02-.04-.11.07.05.08.09-.11ZM213.73,22.35s.03,0,.04-.02c.08.02.13,0,.15-.07,0-.02,0-.03-.02-.04l-.04.02s-.03.05-.07.02l-.04.06v.03ZM214.34,21.93l.04-.06v-.06s-.04-.04-.04-.04v.03s0,.05-.02.06l-.04.06h.06ZM214.36,21.54l.15-.23h-.06s0,.02,0,.02c.02,0,.03.03.02.07-.05.03-.08.06-.08.08l-.02.09v-.03ZM214.56,21.55s.03,0,.04-.02l.09-.11v-.03s-.02,0-.02,0l-.12.1.02.07ZM214.67,21.31s.06,0,.11-.04c0,0-.01,0-.03,0t0,0s-.07,0-.08.05ZM214.86,21.22v-.06s-.05.02-.05.02h-.03s-.02.02-.04.02l.06.04.07-.02ZM214.91,20.97v.03s.06,0,.06-.02c0-.02,0-.06-.04-.11l-.09.11.07-.02ZM214.99,20.92s0-.03,0-.03c.02,0,.03,0,.03,0v-.03s.01-.02.02-.06h-.06s.02.06.02.06v.06ZM214.93,20.72l.06-.12v-.03s-.02,0-.02,0l-.06.12v.03s.02,0,.02,0ZM215.12,20.76s0-.04.01-.06c.03-.04.07-.07.12-.1l-.04-.11h-.03s-.02.09-.02.09v.03s-.05.05-.06.09c0,.02-.02.04-.04.06v.03s.06-.02.06-.02ZM215.32,20.44s-.01-.05.01-.06c.05-.01.07-.03.08-.05v-.06s-.06.02-.06.02l-.05.09-.08.05.09.02ZM215.61,20.01s.02-.03.04-.02h-.06s-.01-.02-.03-.02c0,0,0,.01,0,.03l.02.07.04-.06ZM215.78,19.66c.05-.03.08-.07.09-.11l-.11.07s0,.03.02.04ZM215.92,19.65s.06,0,.07-.02c0-.02,0-.03-.02-.04l-.07.02s0,.03,0,.03c.02,0,.03,0,.03,0ZM216.28,19.17s.03-.07.05-.09h-.03s-.05.08-.05.08v.03s.03-.02.03-.02ZM216.73,18.29s.03-.02.08-.05l.2-.32v-.06s.02-.03.02-.03c-.03.02-.06.02-.1.01l-.04.02c.03.05.05.08.05.08,0,.02-.02.03-.04.02s-.03,0-.04.02c-.02.1-.06.17-.11.21l-.02.09ZM216.91,17.31c.08-.05.11-.07.11-.07l-.06-.04s-.03.05-.08.08l.02.04ZM217.09,17.09s0-.03-.02-.04l-.05.06.02.07.05-.09ZM217.22,16.95l-.06-.04-.04.02s0,.01,0,.03c0,0,.01,0,.03,0l.07-.02ZM218.16,16.53l.11-.07-.06.12-.04.02-.02-.07ZM218.61,17.02s.03-.05.08-.08l-.02-.04s-.07,0-.08.05l.02.07ZM218.28,16.46c.01-.06,0-.09-.05-.08,0-.02.03-.05.08-.08h.03s.03-.02.07-.01c0,.04-.03.07-.05.09,0,.02-.03.05-.08.08ZM218.52,15.96l.09-.11.03.04-.12.1v-.03ZM218.72,33.58s-.05-.03-.08-.08v.06s-.09-.11-.09-.11l-.03-.04c-.06-.03-.15-.07-.27-.09-.04-.03-.1-.05-.18-.07-.02,0-.05-.01-.09-.02-.02.02-.07,0-.12-.03l-.18-.07s-.09-.05-.15-.07c-.07,0-.12,0-.16,0l-.09-.02-.39-.18-.09-.02s-.05-.03-.08-.08l.04-.02c.04-.08.09-.11.15-.1.06.01.1.02.12.03.02.03.03.03.03,0,.02,0,.04,0,.06.01-.04,0-.07-.03-.09-.05-.1-.02-.18-.05-.21-.08,0,0-.01,0-.03,0,0,0,0-.01,0-.03v-.03c.1-.02.17-.05.22-.08-.09.02-.17.03-.23.02-.11.02-.19,0-.22-.05-.12-.07-.22-.1-.31-.1-.05.01-.11,0-.19,0-.17-.04-.33-.15-.49-.33-.21-.24-.4-.62-.57-1.14-.15-.34-.24-.59-.3-.75-.1-.37-.15-.64-.15-.82-.02-.33.02-.68.1-1.06l.04-.19c.02-.1.07-.16.13-.17.02,0,.04-.02.05-.09l.13-.3v-.06s.1-.08.1-.08l-.02.09-.07.31v.06s.07.08.07.08v-.06s.15-.63.15-.63v-.03s.14-.17.14-.17c.05-.03.08-.05.08-.05l.02.07v.06s.06-.05.06-.05l.07-.15c.06-.07.09-.13.1-.17.04-.17.07-.29.11-.37,0-.04.04-.12.08-.24.05-.14.12-.27.21-.38.08-.07.14-.13.17-.19.06-.07.12-.14.17-.19,0-.02,0-.04.01-.06.03-.02.03-.04.01-.06v-.03c.06-.03.11-.09.17-.16.08-.09.15-.16.21-.22.02-.02.04-.03.04-.06,0-.04.03-.07.05-.09,0-.02.03-.05.08-.08s.07-.08.07-.15h.03c.07,0,.08-.02.05-.05-.01-.05,0-.07.01-.06v-.03c-.05-.03-.06-.07-.03-.11.11-.11.18-.19.22-.25l.04-.06-.07.02c-.06.07-.12.15-.18.22-.06.05-.1.1-.13.14-.08.07-.18.18-.3.33-.06.1-.16.24-.29.43-.12.17-.21.34-.27.5,0,.02-.03.06-.09.11-.03.04-.03.07.01.1-.04,0-.08,0-.11.04,0,.04-.02.07-.02.09-.05.03-.11.11-.18.22l-.15.39c-.02.08-.05.14-.1.17-.05.03-.08.09-.1.17l-.04.06.05-.22c.02-.1.07-.17.14-.2,0-.04.01-.06.01-.06.05-.23.13-.42.25-.57l.18-.22.09-.11.03-.13.31-.52c.12-.24.3-.47.54-.7.49-.55.96-.99,1.4-1.33.38-.35.68-.61.88-.76,0,0,.1-.07.3-.2.16-.14.29-.23.39-.28l.62-.45c.16-.14.42-.34.79-.62l.55-.41.48-.26c.05-.03.11-.06.18-.09.08-.05.13-.11.17-.19.03-.06.15-.15.36-.28.08-.07.18-.15.31-.23.13-.08.24-.16.34-.22l.14-.2c.06-.16.19-.28.4-.34l.71-.24.12-.1.08-.08c.07,0,.26-.1.58-.27l.35-.09c.19-.09.34-.17.44-.23.17-.07.41-.12.72-.14.13,0,.32.04.57.09h.13s.29.03.29.03c.09,0,.16.01.22.05.06.01.11.02.16.03.12.03.21.08.26.15.07.06.17.12.29.19.14.05.24.1.3.13l.6.42s.07.11.22.34c.02.03.02.06.01.1.05.36.03.63-.07.8-.04.1-.12.22-.24.37l-.21.51s-.06.07-.09.11c-.03.02-.05.04-.08.08l-.17.16c-.09.2-.16.34-.22.41,0,.04-.1.16-.27.37l-.12.1s-.02.05-.05.09c-.03.02-.05.01-.06-.01-.02,0-.03,0-.04.02-.09.13-.23.29-.4.47-.14.17-.31.37-.49.61l-.2.19c-.05.03-.08.09-.1.17-.05.12-.14.18-.27.17l-.16.13c-.12.17-.28.33-.47.49-.3.28-.47.46-.5.51-.25.27-.57.54-.96.81l-.46.16-.11.07-.15.1c-.06-.01-.1-.03-.12-.06-.05-.08-.14-.12-.27-.12-.16.03-.31.05-.44.07h-.19c-.29-.07-.47-.31-.54-.71,0-.07-.04-.17-.1-.32-.11-.29-.14-.53-.07-.74.03-.13.11-.3.25-.54.15-.21.29-.38.41-.53.12-.15.23-.29.32-.42l.31-.36v-.06s-.03,0-.05-.01c-.02-.03-.03-.03-.03,0-.07,0-.15.04-.25.11l-.79.48-.8.51s-.16.13-.55.44l-.85.6c-.21.17-.43.37-.65.58-.08.07-.14.13-.17.19-.03.06-.07.11-.1.14l-.43.46-.41.53v-.03s-.06,0-.07.05c-.03.06-.08.12-.14.2-.05.05-.1.12-.14.2l-.34.65-.11.37-.02.09.06.04.05-.06s.02-.04.04-.06c.03-.02.04,0,.06.04.02.03.03.05.05.08.02,0,.03.02.03.04-.02.08-.05.14-.1.17,0,0-.05.03-.15.1v.03c-.06-.06-.12-.06-.2,0-.14.12-.22.26-.25.4-.02.02-.05.01-.06-.01h-.03s-.06.02-.04.05c.02,0,.03.02.02.04,0,0,.02.03.05.08l.05-.09v-.06s.11-.01.11-.01l.09.02s-.03,0-.04.02l-.13.17-.05.09v.06s.04.08.04.08l.05-.09.16-.29.03.33.06.5.05.08.05-.09.04-.06v.03c.03.05.04.09.04.11-.02.02-.05.04-.08.08-.03.02-.06.02-.1.01,0,0-.01,0-.04.02,0,0,0,.01.02.04.03.05.01.08-.05.09-.02.02-.04.05-.05.09.04.21.12.37.22.51.05.06.09.12.12.19l-.08.08h-.03s-.04-.03-.06-.05c-.02-.03-.01-.05.01-.06l-.02-.04s0,0-.03,0c0,0,0,.01,0,.03l-.02.09c-.02.08.02.17.11.25.02,0,.04.02.06.04.04.03.04.06.01.1,0,0,.02.05.07.15l.02.07c-.04.06-.03.1,0,.13.04,0,.09,0,.13,0,.23.03.54.04.91.03.35-.01.62-.03.8-.06h.03s-.21.06-.21.06l-.04.02h.06s.23.03.23.03c0,0,0,.01,0,.03,0,0,0,0,.03,0-.02,0-.03,0-.04.02-.14.04-.22.06-.25.08-.07,0-.12.02-.17.03-.02.02-.05.03-.08.05-.02,0-.03,0-.04.02,0,0,0,.01,0,.03,0,0,0,0,.03,0,.06.01.13.05.21.11l.25.05v.03s.06.01.06.01l.27-.04h.03s-.02.04-.04.03l-.5.06-.45.1-.23.02-.37.05h-.06c-.01-.06-.05-.08-.12-.07-.05.01-.09.01-.13,0-.02-.03-.03-.04-.06-.04l-.09-.05c-.03-.05-.11-.07-.22-.05l-.12-.03s-.03-.02-.02-.04h.03s.04-.02.04-.02l-.05-.04c-.12-.07-.2-.11-.24-.12l-.38-.05-.3.03s0-.06-.02-.07h-.13s0,.04,0,.04c0,0,0,.01,0,.03,0,0,.01,0,.03,0h-.06s-.02-.08-.02-.08v.06s-.03.06-.03.06c-.04,0-.06-.01-.06-.01-.02-.03-.04-.03-.06-.01,0,.02-.04.02-.1.01v-.03s.04,0,.04-.02l.14-.07-.02-.07s-.09-.02-.16-.03c-.06-.03-.1-.02-.14.04,0,.02-.02.03-.04.02l-.11.07c.03.05.06.08.08.08.04.03.1.05.18.07,0-.02.02-.03.04-.02,0,0,0,.01,0,.03,0,0,.01,0,.03,0,0,.04,0,.07.05.08h.13s.06.07.08.08c.02,0,.06,0,.11-.04-.02,0-.03-.03-.02-.07l-.16-.03s0-.03-.02-.04h.03s.17-.02.17-.02c-.02-.03-.01-.04,0-.03.02,0,.03,0,.04-.02v.06s.06-.02.06-.02h.03s.08.05.12.03c.05-.01.08-.02.1-.01l.22.02.25.05s.07.03.09.05l-.07.02h-.29s-.03,0-.04.03c0,.02.01.04.06.04l.12.03c.06.01.12,0,.17-.03.02,0,.03.02.02.04l-.07.02.06.04.16.03c.12.03.27.04.45.03.02,0,.03.02.03.04l-.11.04s-.03,0-.04.02h.03c.08.02.15.03.2.02l.02.04h-.03s-.08.04-.08.04l.09.02.22.05.07-.02.21-.05s0-.02,0,0c.02,0,.03,0,.03,0l.09.02c.04-.06.08-.07.14-.04.02,0,.07-.02.15-.07.02,0,.04-.01.04-.06l-.07.02c-.13.01-.23.02-.29,0l-.07.02v.03s-.07-.02-.06-.04c0-.02.02-.03.04-.02.05-.03.11-.04.17-.03l.31-.06h.03s0,.04,0,.04c-.03.02-.04.03-.04.06.02,0,.03,0,.03,0,.02.03.05.04.09.05.09-.02.16-.03.2-.02v-.03s-.02,0-.02,0c0-.02,0-.03-.02-.04,0-.02.02-.03.04-.02l.07-.02c.34-.06.64-.07.89-.04h-.1s-.04.04-.04.04h.06s.04-.01.04-.01v.06s.01.04.01.04h.36s.47-.02.47-.02l.06.04s-.03,0-.04.02c-.05.01-.13.04-.25.08l-.53.18.36-.02c.11-.02.21-.04.28-.07.09-.02.17-.04.24-.05l.18.07h.1s.1-.02.1-.02h.06c.14,0,.24-.02.31-.05.12-.04.26-.08.42-.11.16-.05.33-.1.49-.16l.21-.08h.03s0,.04,0,.04l-.78.26c-.14.06-.35.12-.63.19l-.08.05h.06c.11.02.33-.02.68-.1.12-.04.24-.07.38-.08,0-.02,0-.03,0-.03.02,0,.03,0,.03,0l1.25-.32h.06s-.04.04-.04.04l-1.02.34s-.03.02-.08.05c0,0-.03.02-.08.05.06.01.1,0,.1-.01l.48-.09c.35-.12.53-.18.53-.18l.49-.12c.07,0,.12-.02.17-.03.07,0,.12-.02.17-.03l.42-.11.21-.05s0-.02,0,0c.02,0,.03,0,.03,0v.03s-.06,0-.11.04c.06.01.11.01.13,0l.42-.14.11-.04v.03s-.01.03-.01.03h.03s.18-.05.18-.05h.06s-.03.02-.04.04l-.52.28-.84.41c-.14.06-.3.11-.46.16-.16.05-.33.11-.5.19-.3.07-.55.14-.77.23l-.09-.05h-.03s-.01,0-.04.02c0,0,.01,0,.03,0,.01.05,0,.08-.05.09-.02.02-.05.02-.07.02-.38.14-.64.22-.78.26-.33.1-.51.16-.56.17-.05.03-.1.04-.14.04-.03.02-.05.02-.07.02h-.03s0-.04,0-.04l.26-.14.49-.12.21-.05s.03-.02.08-.05l-.09-.02-.35.09c-.12.04-.25.07-.41.08-.16.05-.4.11-.72.17-.05.01-.07.03-.08.05,0,.02-.02.04-.05.06l.02.07s.02-.06.04-.06c.04,0,.07.02.09.02l.18-.06.14-.04.09.02-.04.06-.39.11c-.07.03-.13.03-.16,0l-.08.05h-.1c-.06,0-.11,0-.13.02-.03.06-.1.09-.18.09-.07,0-.12.02-.17.03l-.21.05s.1-.09.2-.15l.11-.04s0-.03-.02-.04l-.12-.03c-.08-.04-.15-.05-.22-.05-.07.03-.16.04-.27.04-.11.02-.2.03-.27.04h-.03s.01-.07.01-.07c-.04-.03-.09-.03-.16,0l-.02.09v.03s-.07,0-.08.02l-.15.07c.06.01.11.01.13,0,.06.01.12,0,.17-.03h.03s-.02.04-.04.03c-.06.05-.1.09-.12.1-.25.14-.51.16-.8.06ZM215.78,31.77l-.13-.16-.08-.08-.04.02s0,.06.02.07c.11.09.18.15.19.17h.03s0-.02,0-.02ZM216.02,31.69s.03,0,.04-.02h-.03c-.06-.04-.16-.07-.31-.11v.03s.3.1.3.1ZM215.4,30.02s-.01,0-.03,0c0,0,0-.01,0-.03v-.06s-.04-.08-.04-.08l-.07.02s.02.03.05.08l.02.07h.06ZM215.27,29.73l-.04-.11-.07.02.07.11.04-.02ZM216.9,32.17v.03s.06.01.06.01l.46-.03c.08.02.1-.01.05-.09-.03-.05-.05-.06-.06-.01l-.07.02s-.05,0-.1.01c-.03.02-.05.01-.06-.01-.02-.03-.11-.04-.29-.03h-.13s-.1.02-.1.02h-.03s0-.07-.05-.08c-.02.02-.04.01-.03,0-.02,0-.03,0-.04.02-.03.02-.06.02-.1.01-.05.01-.08,0-.09-.02-.03-.05-.09-.08-.17-.1l-.11-.09h-.06s.05.06.05.06l.43.26.16.03h.29ZM216.38,31.24l-.11-.09-.04.02s.05.03.08.08l.07-.02ZM216.58,31.38s.03,0,.04-.02c-.07-.06-.14-.1-.2-.11h-.03s0,.02,0,.02c.02,0,.03,0,.03,0,.07.06.13.09.17.1ZM215.17,29.57s.04-.01.04-.06l-.02-.07-.06-.18s0-.06,0-.13c0-.09-.03-.16-.08-.21h.03s0-.02,0-.02c0-.07,0-.12.03-.16l-.06-.04h-.03s-.06-.05-.06-.05v.03s.03.14.03.14c.01.13.03.25.06.34,0,.02,0,.08.03.17l.05.21.03.04ZM216.86,31.9s.06,0,.07-.02c.01-.06.07-.08.18-.06v-.03s-.02,0-.02,0l-.12-.03c-.12-.03-.21-.06-.24-.09l-.07.02s.03.02.02.04c.02.03.03.04.06.04.04,0,.07.03.09.05,0,.02,0,.03.02.04.02,0,.03.02.03.04ZM216.16,30.28s-.04-.06-.12-.19l-.04.06c.07.06.13.11.16.17v-.03ZM217.27,31.83l-.02-.04s-.06,0-.11.04h.03s.1,0,.1,0ZM214.99,28.58s.07,0,.07-.02l.02-.09-.06-.04.04-.19.04-.35-.06-.04-.05.06-.05.22v.4s.03.07.03.07ZM215.59,28.98l-.05-.08v.03s.04.11.04.11v-.06ZM215.56,28.84v-.13s-.05.06-.05.06l.04.11v-.03ZM217.41,31.5s.03,0,.04-.02h-.03s-.21-.09-.21-.09h-.03s-.07.01-.07.01l.02.04.28.06ZM216.39,29.97l-.07-.11h-.03s.05.08.04.1c.02,0,.03.02.02.04h.03s0-.02,0-.02ZM215.53,28.67v-.13s-.04.01-.05.06v.1s.05-.02.05-.02ZM215.97,29.35s0-.08-.01-.1v-.06s-.08-.03-.07-.05c0-.04.01-.07.02-.09h-.03s-.01,0-.04.02c0,0,.01,0,.03,0-.02.08,0,.16.05.24,0,.02,0,.03,0,.03.02,0,.03,0,.03,0h.03ZM216.34,29.6s0-.08-.03-.17v.16s0,.03,0,.03c.02,0,.03,0,.03,0v-.03ZM215.67,28.8c0-.09,0-.18,0-.26,0-.11,0-.21-.03-.3,0-.02,0-.03,0-.03.02,0,.03,0,.03,0l.04.6h-.03ZM215.48,28.3s.03,0,.03,0c0-.02,0-.03,0-.03v-.3s0-.03-.03-.04v.03s-.02.15-.01.33ZM217.48,31.61c.08.02.16.02.23.02.08.04.19.07.34.11l.14-.04-.09-.05-.34-.07c-.06-.03-.1-.04-.12-.03,0,.02-.02.03-.04.02v-.03s0-.03-.02-.04h-.03s0,.07-.02.09c-.02,0-.04,0-.06-.01l-.04.02s.06.01.06.01ZM218.07,31.9l-.06-.04-.07.02.09.05.04-.02ZM218.7,32.63l-.02-.04-.15.07.02.04.15-.07ZM218.76,33.39l.33-.03s.02-.02.08-.05l.04-.02v.03s.05.04.05.04l.04-.02s.02,0,0-.03c0,0-.02-.03-.05-.08l.04-.06.09.02-.06-.04h-.03s0-.04,0-.04c.02,0,.03,0,.03,0,.09-.02.16-.05.21-.08l.08-.05-.09-.02-.09-.02-.09-.02-.34.06s.04-.05.05-.09l-.09-.02s-.02.03-.04.02h-.06c.05-.05.08-.06.08-.06l.04-.02.09.02c.12.03.26.02.4-.01l.04-.06h-.06s-.2,0-.2,0l-.02-.04c.05-.03.06-.06.02-.09-.04,0-.06-.02-.06-.04,0,.02-.03.03-.07.02l-.08.05-.24.05c-.07.03-.09.07-.06.12,0,.02-.03.04-.08.05-.03.04,0,.05.09.05l.02.07s-.06,0-.11.04l-.37.05s-.03.05-.08.08c.02,0,.03,0,.03,0,.02.03.04.03.06.01.06.01.2.02.42.03l.06.04-.07.02-.07.02.08.08h.03ZM218.46,31.92c.08-.05.11-.07.11-.07l-.05-.04c-.05.03-.09.05-.11.04,0,.04,0,.07.05.08ZM219.53,33.2l-.02-.04s-.03.02-.08.05l.06.04.04-.06ZM215.9,29.99c.05-.03.08-.06.08-.08.01-.06,0-.13-.05-.21l-.09-.35c-.01-.13-.04-.28-.07-.44,0-.16-.02-.32-.02-.5l-.02-.04h-.03s.03-.13.03-.13c0-.22,0-.38-.02-.5v-.16s.06-.12.06-.12l.03-.29c.04-.1.09-.23.15-.39.06-.16.1-.29.11-.37l.1-.17c.06-.07.13-.21.22-.41l-.02-.04s-.03.03-.07.02l.04-.06v-.06s.01-.03-.01-.04l-.04.02-.15.23c-.06.1-.15.28-.25.57-.04.1-.09.24-.13.43l-.16.75-.03.29.04.4c-.02.21-.02.43.02.66.04.21.07.34.07.41l.06.18v.06c-.05,0-.06.01-.03.06.01.05.05.12.12.22,0,.02,0,.03.02.04.02,0,.03,0,.03,0ZM217.52,30.08s0-.03,0-.03c.02,0,.03,0,.03,0,0-.02,0-.03-.03-.04,0-.02,0-.04.01-.06l-.05.09s0,.01,0,.03c0,0,.01,0,.03,0ZM218.62,31.5v-.03s-.05-.04-.05-.04h-.06s-.07-.02-.07,0c.02,0,.03.02.03.04h.03s.12.03.12.03ZM216.14,27.98l.07-.8s-.01,0-.03,0c0,0,0-.01,0-.03v.06s-.04.13-.04.13c-.04.17-.06.38-.07.64l.02.04.04-.02ZM217.47,30.73s0,.03,0,.03c.02-.02.04-.03.04-.06.04,0,.07,0,.08-.05l-.09-.18c-.05-.18-.09-.33-.14-.42v-.06c.07.03.1.03.08-.02,0-.04.01-.06.01-.06l.08-.08.05.08s.02.03.05.08l.04-.02-.04-.11s0-.03-.02-.04v.03s-.06-.04-.06-.04l.07-.02s.01-.06.01-.06l-.05-.21c-.07-.19-.1-.35-.09-.48.01-.06.01-.16,0-.3l.04-.51s0-.06-.04-.11l-.02.09s-.03.13-.12.24c0,0-.01,0-.04.02,0,0,0-.01,0-.03l-.02-.07.02-.23-.02-.04v.03s-.02.06-.02.06c-.01.06-.02.15-.02.26,0,.09-.01.16-.05.22.01.05,0,.09-.03.13,0,.04-.02.08-.03.13-.02.1-.05.33-.08.67,0,.02,0,.04-.01.06.02,0,.02.01,0,.03-.03.04-.05.09-.07.15-.01.06-.01.12,0,.16l.18.37s.03.02.02.04l-.09-.02-.04.02s.02.05.02.07c0,.02,0,.03.03.04.06.03.18.11.38.21ZM216.36,27.7s.06,0,.07-.02c.03-.04.05-.07.05-.09l-.02-.04-.11.07.02.07ZM216.95,28.45l.03-.16.02-.09-.02-.07-.04.06s0,.13-.02.26c0,0,0,.01,0,.03,0,0,0,0,.03,0v-.03ZM216.44,27.49c.02-.1.03-.18.02-.23l.02-.09h-.03s-.04.05-.04.05l-.02.26v.06s.06-.05.06-.05ZM218.89,31.16c.08.02.17,0,.27-.04h.03s-.03,0-.03,0c0-.02,0-.03,0-.03l-.3.03s0,.01,0,.03c0,0-.01,0-.03,0h.06ZM217.04,27.72l.09-.41.02-.09-.02-.04-.04.02-.09.11s-.02.03-.04.02h.06s0,.04,0,.04c.02,0,.03,0,.03,0v.19s-.04.13-.04.13l.02.07v-.06ZM220.75,33.3s.06,0,.11-.04l-.02-.04-.11.04s.02.04.02.04ZM216.78,27.27s-.01-.05.01-.06c.03-.04.05-.07.05-.09.06-.05.07-.09.06-.12.02-.08.05-.13.1-.14v-.06s.04-.08,0-.13c-.01-.05-.03-.08-.04-.11,0-.02,0-.03-.02-.04,0-.02,0-.03,0-.03.02,0,.03,0,.03,0h-.03s-.01.06-.01.06l-.04.06h-.03s0-.04,0-.04l-.04.02-.07.31h-.03s.03.16.03.16l-.04.02s-.03,0-.04.02c.02.03.03.04.03.04,0,.02,0,.06.04.11v.03s.03-.02.03-.02ZM216.41,26.4s.02-.03.04-.02l.1-.31v-.03s-.03,0-.03.02l-.12.27.02.07ZM219.95,31.85v-.06s.08-.02.08-.02v.03s-.01.03-.01.03c0,0,0,.01,0,.03.02,0,.03,0,.04-.02l.27-.04v-.03s.05-.06.05-.06l.28-.07s.03,0,.04-.02c0,0-.01,0-.03,0,0,0,0,.01,0,.03-.04,0-.11,0-.2.02-.09.02-.18.04-.27.04-.07,0-.13.01-.2.02l-.11.04v.03s0-.03,0-.03l.06.04h-.03s-.01.06-.01.06l.07-.02ZM217.18,27.09l.15-.52-.02-.07-.04.06-.02.09s0,.02-.01.06c.01.05,0,.08-.02.09,0,.04-.03.07-.05.09.01.05,0,.11-.01.19,0,.02,0,.03,0,.03.02,0,.03,0,.03,0v-.03ZM216.5,26.59s.03-.02.08-.05v.06s-.02.03-.02.03c.02,0,.03,0,.04-.02.03-.13.06-.22.09-.27.08-.16.15-.27.21-.35.04-.1.13-.24.26-.44l.15-.23v-.03s-.03,0-.03.02l-.31.39-.11.21-.07.02v-.06s.16-.23.16-.23c.16-.32.3-.54.44-.66,0,0,0-.01,0-.03,0-.02,0-.04-.02-.07h-.03c-.1.06-.17.11-.2.15l-.28.4-.15.23c-.08.16-.12.26-.13.3v.03s.02,0,.02,0c0-.02,0-.03,0-.03l.16-.26-.14.33c-.04.08-.08.17-.12.27-.04.1-.08.22-.11.37-.02.1-.03.19-.02.26l.14-.33ZM221.38,32.81s.03-.05.08-.08c-.02,0-.06,0-.11.04l.02.04ZM216.99,26.43s.04-.06.08-.05c.04.03.07,0,.08-.08l.04-.02.02.04.04-.06s0-.05-.01-.1c.01-.06.03-.1.06-.12l.04-.19.09-.11s-.06-.02-.06-.04c.03-.02.04-.02.04-.02l.1-.17v-.03s-.02,0-.02,0v.03s-.02,0-.04,0c0-.02.02-.03.04-.02v-.06s.03-.06.03-.06c0,.02-.02.03-.04.02l-.14.2c-.19.29-.32.57-.38.87v.03s.03-.02.03-.02ZM217.26,25.96c.06-.07.09-.11.09-.11h-.03s-.09.1-.09.1l.03.04v-.03ZM217.45,26.3c.01-.06.05-.15.12-.27h-.06s-.09.23-.09.23v.03s.02,0,.02,0ZM221.4,32.39l.18-.06s-.03,0-.03,0c0-.02,0-.03,0-.03l-.18.06v.03s.03,0,.03,0ZM220.44,30.78s.05-.02.07-.02c.04,0,.07,0,.1-.01v.03s-.18.03-.18.03v-.03ZM217.61,25.39c.01-.06.05-.13.11-.21v-.03s0,.03,0,.03l-.17.16.03.04h.03ZM222.76,32.62v-.03s-.02.03-.06.02c-.04-.03-.07-.04-.09-.02,0,.02-.02.03-.04.02l-.06-.04-.04.02c.03.05.05.08.05.08l.24-.05ZM217.37,24.09l-.06-.04-.12.1h.03s.14-.06.14-.06ZM218.04,24.79h-.03s-.08.07-.08.07c.02,0,.03.02.02.04l.09-.11ZM223.07,32.56v-.03s-.06-.01-.06-.01l-.14.04-.04.02s0,.03,0,.03c.02,0,.03,0,.03,0l.21-.05ZM223.21,32.68c.07,0,.17-.04.32-.1l.04-.02s0-.03-.02-.04l-.42.11s-.04.01-.04.06h.06s.07,0,.07,0ZM217.89,23.51h-.03s-.2.18-.2.18c.02,0,.03.02.02.04l.21-.22ZM218.34,22.92v-.03s-.03.02-.03.02l-.17.16v.03s.2-.19.2-.19ZM219.23,23.8l.36-.28-.02-.04s-.02.06-.04.06c-.07,0-.13.04-.18.09-.03.06-.08.1-.13.14v.03s.02,0,.02,0ZM219.43,22.73v-.03c.06-.03.09-.05.11-.04.06.01.1-.01.11-.07v-.06s.35-.19.35-.19l.08-.05.17-.16c.07-.03.16-.1.27-.2.02,0,.03,0,.04-.02.01-.06.07-.08.18-.06l.15-.1.19-.12v-.03s0,0-.02,0c0,0,0,.01,0,.03l-.16.13s0-.06-.02-.07c-.04,0-.04-.03.01-.06,0-.04.03-.07.05-.09h-.1s-.33.2-.33.2c-.12.13-.27.26-.48.39l-.09.11c-.13.08-.19.12-.19.12l-.4.34-.09.11h.06s.11-.06.11-.06ZM221.11,21.46l-.02-.07-.04.02s0,.07.05.08v-.03ZM221.21,21.48s.07,0,.07-.02c0,0,.04-.02.11-.07l.27-.17s.04-.05.05-.09c.03-.02.03-.03,0-.03,0-.02,0-.03,0-.03l-.07.02-.04.06-.34.22-.08.08s0,.03,0,.03c.02,0,.03,0,.03,0ZM219.74,23.29s.05-.02.07-.02c.02,0,.05-.01.08-.05.05-.01.09-.04.12-.07.05-.05.11-.1.16-.13.09-.11.19-.21.29-.3.11-.11.22-.2.32-.29l.81-.58.46-.33.36-.31.27-.2.26-.14c.08-.07.17-.13.27-.17,0-.02.02-.03.04-.02.02-.02.03-.04.01-.06h.03s.14-.03.14-.03l.34-.22s.05-.03.15-.1l-.02-.07-.04.02-.3.16-.72.43-.35.25-.39.28-.47.36-.16.13s-.06.03-.11.04c-.05.01-.08.03-.11.04l-.08.08-.31.23c-.24.21-.38.32-.4.34-.02.02-.12.1-.29.27l-.37.35-.11.07.02.04ZM221.89,21.04s.04-.05.05-.09h.03s.2-.18.2-.18h-.03c-.1.04-.15.1-.17.19-.05-.06-.09-.05-.1.01,0,.02-.02.03-.04.02l.06.04ZM224,20.22l.11-.07-.02-.04-.12.07v.03s.03,0,.03,0ZM224.12,20.11s0-.03,0-.03c.02,0,.03,0,.03,0,0,0,.1-.07.3-.2v-.03s-.02,0-.02,0l-.3.2v.03s-.01.03-.01.03ZM228.95,35.56c-.1-.02-.19-.08-.25-.19l-.12-.06c-.15-.03-.26-.11-.34-.24-.08-.04-.14-.1-.19-.17-.07-.08-.17-.13-.29-.16-.03.02-.07,0-.12-.03-.06-.03-.11-.06-.15-.06l-.37-.28c-.11-.22-.24-.39-.41-.51-.11-.09-.2-.14-.26-.15-.1-.02-.16-.1-.18-.24-.03-.07-.14-.17-.33-.3-.15-.1-.3-.32-.45-.65-.03-.07-.08-.31-.17-.72-.01-.13,0-.25.04-.35h-.03s.17-.33.17-.33c.08-.16.12-.27.14-.33l.12-.24c.05-.03.1-.09.13-.17s.06-.13.07-.15c-.05-.08-.06-.13-.03-.17.06-.05.09-.09.09-.11.05-.14.13-.26.24-.34.1-.15.2-.34.32-.55.04-.1.14-.24.29-.43.06-.07.24-.31.54-.7.11-.2.21-.35.3-.46.09-.13.17-.25.24-.34.14-.14.28-.32.41-.53.13-.08.21-.21.24-.37l.06-.12.14-.2s.04,0,.07-.02c.02-.02.04-.03.04-.06l.08-.08c.24-.3.38-.49.42-.56.12-.13.22-.25.31-.36.09-.13.17-.24.23-.31l.36-.45c.03-.06.1-.16.2-.32.1-.15.2-.28.31-.39.15-.17.24-.31.29-.43l.3-.46c.08-.07.14-.13.17-.19.04-.08.07-.14.1-.17.01-.06.07-.15.15-.26.05-.01.06-.04.05-.09.01-.06.01-.11,0-.13l-.16-.17s0-.04-.02-.07c0-.04.03-.07.05-.09.02-.1.02-.18-.01-.23v-.06s.04-.13.04-.13c-.01-.16.05-.23.18-.22.05-.03.13-.06.25-.08.27-.05.51-.14.71-.27.04,0,.07-.02.08-.08l.41-.67s.04-.08.03-.13c0-.04.03-.09.07-.15.03-.04.08-.1.14-.2.09-.11.18-.18.27-.2.18-.11.38-.15.61-.1.21.05.36.09.46.13.1.04.19.13.27.26.06.03.11.08.17.13.05.06.11.1.17.13.01.05.06.1.13.16.1.06.16.11.2.14l.23.28c.03.05.08.08.14.1.22-.02.4-.05.55-.11.48-.11.94-.19,1.36-.23.33-.1.65-.17.96-.19.29-.05.52-.05.69-.01l.22.05.28.06s.07.03.15.06c.08.02.14.06.17.13.02.03.05.04.09.05.04,0,.08.03.12.06.02.03.05.04.09.05.02,0,.03.02.02.04h-.03s-.04,0-.07.01c0,.02,0,.03,0,.03l.02.07-.04.02v.1s.22.08.22.08c0,0,.02.03.05.08.02.03.03.06.04.11.02.03.03.07.03.14-.01.06,0,.11.04.14.04.03.06.06.08.08.02,0,.04.06.06.18.04.03.06.06.08.08.04.03.06.06.08.08.07.1.07.2,0,.3-.03.13-.06.22-.09.27v.19c0,.09-.02.17-.06.25l-.17.36-.14.2h-.06c-.03-.06-.02-.13.04-.2.03-.02.04-.05.05-.09.01-.06.01-.11,0-.13-.01-.05-.02-.09-.03-.14-.01-.05-.06-.08-.14-.1-.02,0-.04.01-.04.06l-.04.06v-.06s0-.07,0-.13l-.19-.04-.09-.02c-.06-.03-.14-.05-.25-.05-.32.06-.56.1-.71.11-.27.05-.68.12-1.22.19-.44.04-.77.07-.97.12-.11.02-.28.05-.51.09-.22.02-.41.02-.56.01-.07,0-.15.02-.24.05-.07,0-.15.02-.24.05-.13.01-.2.02-.2.02-.13.01-.24.01-.33,0-.02.02-.07.03-.14.04-.06-.01-.1,0-.1.01l-.1.14-.39.57c-.06.07-.15.18-.26.3-.09.11-.17.23-.24.34-.15.19-.26.34-.33.45-.09.11-.19.22-.3.33-.09.11-.18.23-.28.37l-.13.14v.03s.06.01.06.01l.41-.08c.13,0,.24.03.34.07.04.03.16.07.37.11.06.01.1.05.1.12.02.03.05.04.09.05.17.1.28.16.32.17v.06s-.04,0-.04,0c-.02,0-.03,0-.04.02,0,.02-.02.03-.04.02.02,0,.03.02.02.04,0,.02,0,.03.02.04l.21.08h.03s.1.13.1.13l-.14.04c-.08-.02-.14-.02-.16,0h-.03s0,.03.03.03l.09.05.31.07s.1.04.17.1c.02.11.06.19.12.22l.18.07c.06.03.08.07.07.11,0,.02-.02.03-.04.02l-.24-.12h-.06s.03,0,.02.02c0,.07.04.13.09.18.08.04.14.07.17.1l.23.31s0,.01,0,.03c0,0,0,0,.03,0l-.09-.02s0-.03-.02-.04c-.02,0-.03,0-.03,0,0-.09-.02-.11-.05-.08-.03.02-.05.02-.07.02v.13s.13.16.13.16c0,0,0,.01,0,.03.02.03.04.04.06.04-.04,0-.08-.04-.11-.09h-.03s-.02-.01-.06-.02v.1c.17.08.27.15.32.23l.11.25.05.08s.03.06-.02.09c-.02.02-.06.02-.1.01l-.17-.13-.26-.15c-.07-.06-.1-.03-.08.08v.03s-.03-.04-.03-.04c-.01-.05-.06-.07-.15-.06l-.99.02-.92.03-.27.04c-.33.02-.65.02-.95.02-.11,0-.22,0-.33.03-.11,0-.24,0-.39-.02-.04,0-.12,0-.23.02-.11,0-.21-.01-.32-.04l-.11.04c-.17.27-.29.44-.37.51l-.16.13c-.18.22-.38.49-.6.79-.09.11-.18.24-.28.4-.07.14-.18.28-.32.42-.33.54-.54.89-.62,1.04-.04.08-.08.17-.12.27-.04.08-.07.18-.1.31-.04.08-.01.12.07.11.07-.03.13-.04.17-.03.07,0,.11,0,.13,0h.03s-.03.01-.04.03l-.35.09s-.04,0-.07.02c0,0-.01,0-.03,0l.12.03.26.02h.06s-.04.04-.04.04l-.3.03c-.07,0-.12.03-.14.07-.03.02-.04.06-.03.13,0,.02,0,.04-.01.06.02,0,.03.02.02.04,0,.04.03.07.11.09l.26.02c.07,0,.15-.01.23-.02.11-.02.22-.02.33,0h.06s.04.02.06.03c.04,0,.07.03.09.05.06.1.13.14.2.11l1.04-.1.44-.07h.06s.11.02.2,0c.09-.02.18-.04.27-.04.05-.01.12-.03.21-.05.12-.04.23-.06.34-.06.02,0,.17-.02.44-.07.14-.01.24-.04.31-.06.09-.02.17-.04.24-.05.17.02.26.01.26,0l.04-.06s.03.02.02.04c0,.02,0,.03,0,.03.08-.05.11-.03.09.05.02.03.04.04.06.04.04,0,.06,0,.07-.02h.03s.06.02.06.02v-.03s.02-.06.02-.06c0-.02.02-.03.04-.02v.03s-.03.09-.03.09c0,0-.03.02-.08.05v.06s-.02.04-.03.06c.02,0,.03.02.02.04.02.03.07.08.16.17.02,0,.03.02.02.04.05.18.1.28.16.3.02,0,.03,0,.04-.02.03-.02.05-.02.07-.02l.04-.02s0,.01,0,.03c.02,0,.04,0,.06.01v.03s-.03.13-.03.13c.02,0,.06,0,.11-.04.05-.03.08-.06.08-.08,0,0,0-.01,0-.03.02-.02.04-.03.04-.06.02,0,.03.02.02.04,0,.02,0,.03.02.04v.03c-.06.03-.08.08-.07.15.02.03.02.07,0,.13.02.11.07.16.17.13.07,0,.12,0,.16.03.04.1.02.2-.07.31-.1.04-.14.11-.14.2,0,.09,0,.14,0,.16l-.07.31-.04.02s-.01,0-.03,0c-.02,0-.03-.02-.02-.04-.06-.03-.09-.09-.1-.15-.01-.05-.03-.06-.06-.04-.11.11-.27.16-.49.16-.11.02-.25.03-.4.04-.13.01-.28.04-.44.07-.13.01-.28.05-.45.1h-.03s-.08-.04-.13,0c-.05.03-.09.05-.11.04l-.04.02-.12-.03c-.04.06-.09.09-.15.1-.07,0-.11,0-.13,0h-.2c-.13,0-.25.07-.33.18h-.03c-.06-.02-.15-.02-.26,0-.11.02-.2.03-.27.04l-.28.07s-.06,0-.11.04c-.06-.01-.09-.02-.09-.02h-.06c-.06-.03-.14-.02-.23,0-.1.04-.18.07-.25.08l-.15.07-.24.05-.09-.02ZM228.55,33.02l.08-.05h-.06c-.06-.03-.11-.02-.14.02l-.04.02h.06s.1,0,.1,0ZM227.24,30.25l.06-.12s0-.03-.02-.04v.03s-.05.06-.07.12h.03ZM228.85,32.95c.1.02.18.03.23.02h.03s-.02-.03-.02-.03l-.23.02h-.03s0,0,0,.02c.02,0,.03,0,.04-.02ZM227.5,29.81c.05-.03.08-.08.1-.14v-.03s-.02,0-.02,0l-.09.11v.06s.02,0,.02,0ZM231.14,34.04s.06-.05.08-.05c.02,0,.04,0,.07-.02l.38-.08c.06.01.14,0,.23-.02l.04-.06-.07.02c-.22,0-.39.01-.5.06-.05.03-.12.06-.21.08-.02,0-.04.01-.04.06h.03ZM231.27,33.44c.14-.04.27-.06.41-.08.13-.01.25-.03.34-.06l.07-.02s-.06-.01-.06-.01l-.43.04s-.1.03-.18.06c-.05.01-.11.03-.18.06h-.03s.03,0,.03,0h.03ZM232.44,33.17c.15-.01.28-.04.38-.08l.12.03-.15-.06c-.14.06-.26.09-.35.09,0,0,0,.01,0,.03,0,0-.01,0-.03,0h.03ZM240.72,22.59v-.06c.03-.06.05-.1.07-.12h.03s-.08.22-.08.22h-.03s0-.04,0-.04ZM234.41,38.41c-.06-.01-.09-.06-.07-.15,0-.02,0-.03,0-.03-.02,0-.03,0-.03,0-.03-.07-.02-.12.03-.16v-.06s.04-.13.04-.13v-.03s-.06.02-.06.02l-.04.06c-.05.03-.08.03-.09-.02,0-.04-.02-.07-.08-.08-.02.02-.03,0-.02-.04,0-.04,0-.11-.02-.2v-.03c-.1-.02-.11-.07-.03-.14l.09-.11v.03s.01.07.01.07l.08-.05-.05-.04h-.03s.32-.3.32-.3c0,0,0,0,.03,0,0,0,0-.01,0-.03h-.03s-.03-.01-.03-.01c0,.02,0,.03,0,.03-.03-.05-.06-.07-.09-.05l-.23.15-.07.02v.03s-.03.03-.08.02c-.04,0-.06-.03-.05-.08,0-.07.04-.13.14-.2.11-.11.18-.2.22-.28.02,0,.03,0,.04-.02-.02,0-.03,0-.03,0h-.03c-.05.03-.12.05-.21.08,0,.02,0,.03,0,.03-.02,0-.03,0-.03,0v-.06s.13-.07.13-.07v-.03s-.05-.01-.05-.01c0,.04-.03.04-.06-.01-.04,0-.07,0-.1.01-.05.03-.08.05-.08.05v-.06s.02-.03.02-.03v-.06c.03-.08.1-.17.23-.25.08-.09.23-.2.43-.33l.38-.25.42-.27s.02-.03.04-.02c.17-.07.51-.29,1.03-.66l.37-.35c.05-.03.13-.09.24-.18.11-.11.23-.18.34-.22l.48-.26.3-.16c.11-.02.22,0,.31.07.12.05.24.13.37.24.04,0,.09.05.14.13.05.06.14.1.27.12.15.03.23.1.25.22v.03s-.02.04-.02.06c.02,0,.04,0,.07-.02.02,0,.03.02.02.04-.07.14-.09.26-.05.38.02.09.03.16.02.2-.01.06-.05.12-.1.17-.03.06-.05.1-.06.12l-.04.02c-.01.06-.05.12-.1.17-.05.03-.09.06-.11.07l-.21.22-.12.1-.45.26-.46.33-.7.54-.37.21-.46.29c-.2.13-.36.22-.48.26l-.11.07-.2.15-.29.13-.63.35s-.05.01-.06-.01c-.04,0-.07,0-.1.01ZM234.32,36.4h-.03s-.11.07-.11.07c0,0,0,0,.03,0,0,0,0,.01,0,.03l.12-.1ZM234.56,36.97l.18-.09v-.03s-.02,0-.02,0c0,0-.05.03-.15.1-.02,0-.03,0-.03,0,0,.02,0,.03,0,.03h.03ZM234.39,36.38l-.06-.04-.07.02s.01,0,.03,0t0,0l.09.02ZM234.39,36.54l.15-.07s.02-.03.04-.02h-.03s-.07-.01-.1,0c-.03.02-.05.03-.08.05v.03s.02,0,.02,0ZM234.59,36.22s0-.01,0-.03c0,0,.01,0,.03,0h-.06s-.03-.02-.03-.02h-.03s-.01.06-.01.06c0,.02,0,.03.02.04l.08-.05ZM234.68,36.41s.03-.06.08-.05l.07-.02.15-.1.12-.07h-.06c-.09.01-.15.04-.18.08-.03.02-.05.03-.08.05-.05.03-.09.06-.12.07-.02,0-.03,0-.03,0,0,.02,0,.03,0,.03l.02.04.04-.02ZM234.83,36.05h-.03s-.07.01-.07.01l.02.07.08-.08ZM234.97,35.98s0-.01,0-.03c0,0-.01,0-.03,0,.06.01.11.01.13,0,0,0,.05-.03.15-.1l.04-.02s0-.03-.02-.04c0,0,0,.01,0,.03,0,0,0,0-.03,0l-.11.07-.15.07s-.03,0-.04.02c-.02,0-.03,0-.03,0,0,.02,0,.03,0,.03,0,.02,0,.03.03.04l.08-.05ZM234.54,36.9l.11-.07c.14-.04.27-.09.4-.18h.03s0,.04,0,.04l-.11.07-.14.07.11-.04s0-.01,0-.03c0,0,0,0,.03,0,.36-.16.52-.24.47-.22v-.03s-.02,0-.02,0c0-.04.04-.07.08-.08.02-.02.05-.02.07-.02.08-.05.15-.09.22-.12.05-.03.1-.07.15-.1.02-.02.05-.03.08-.05.03-.02.04-.05.05-.09h.06s.2-.14.2-.14h-.03s-.23.14-.23.14l-.66.32c-.3.2-.54.32-.7.37l-.19.12v.03s.02,0,.02,0ZM235.34,35.8l.34-.22v-.03s-.06.02-.06.02l-.23.15h-.03s-.04.02-.04.02v.06s.02,0,.02,0ZM235.56,35.81c.1-.07.15-.1.15-.1l.04-.02h-.03s-.19.12-.19.12h.03ZM236.21,35.53v-.03s-.04.03-.15.1l.15-.07ZM236.1,35.31c.05-.03.1-.04.14-.04l-.02-.04h-.03s-.07.01-.07.01l-.04.02.02.04ZM237.25,34.8h-.03s-.03-.01-.03-.01l-.12.1s0,.03.03.04l.16-.13ZM111.55,39.34c.02-.1.05-.17.08-.21.03-.04.04-.09.03-.16,0-.07,0-.12.03-.16.03-.04.04-.09.03-.16,0-.04.03-.08.06-.12l.11-.5s0-.05-.01-.1c-.02-.03-.02-.05-.02-.07-.02-.03-.02-.07,0-.13.02-.08.02-.15.01-.19v-.06s.02-.04.03-.06c.03-.02.04-.05.05-.09v-.06s.02.13.02.13l-.05.09v.03s.02,0,.02,0c.08-.16.13-.29.15-.39v-.03s0-.05,0-.1c0-.04.02-.06.04-.06.05-.03.07-.08.07-.15-.01-.05-.01-.09,0-.13.02,0,.02,0,0-.03,0-.02,0-.03,0-.03.12-.13.14-.22.06-.28-.05-.08-.06-.13-.03-.17.05-.03.08-.05.08-.05l.16-.46c.08-.18.18-.41.28-.69l.15-.39s0-.01,0-.03c0,0,0,0-.03,0v.03c-.11.07-.16.1-.16.1v-.03s.02-.06.02-.06c-.05.03-.08.05-.08.05-.1.15-.16.3-.19.45v.06c-.15.23-.24.41-.29.53l-.27.5s-.06.05-.09.11c-.03.06-.05.1-.06.12l-.07.18c-.07.14-.16.33-.25.57l-.11.21v.03s0-.03,0-.03l.02-.09c.03-.15.09-.27.18-.39.02-.1.05-.18.08-.21.03-.15.07-.25.13-.3.03-.02.05-.08.07-.18l.24-.5c.02-.1.07-.24.15-.39v-.06s.03-.05.07-.09c.03-.04.04-.07.02-.09.03-.02.03-.04.01-.06-.02-.03-.03-.04-.03-.04v-.13c.03-.06.07-.13.11-.21.03-.06.06-.13.08-.21.04-.08.08-.21.12-.4l.15-.39.05-.22.05-.25c.02-.08.07-.22.16-.42v-.03s0,0-.02,0c0,0,0,.01,0,.03-.03.04-.06.08-.1.14-.03.04-.06.08-.1.14-.16.36-.31.62-.43.79l-.08.21s-.02.03-.04.02v-.03s.07-.12.07-.12c0,0-.01,0-.03,0,0,0,0-.01,0-.03v.03s-.11.17-.11.17c-.01.06-.05.13-.11.21-.04.08-.06.14-.07.18v.03s0-.03,0-.03l.07-.15s0-.06-.02-.07c0,0,0,0-.03,0,0,0,0,.01,0,.03l-.08.21s-.05.1-.07.18l-.16.29-.12.27c-.1.24-.18.43-.25.57v.03s0-.03,0-.03l.22-.71.11-.21c.01-.06.03-.13.04-.19.03-.06.05-.13.05-.22l.05-.22v-.03s0,.03,0,.03l-.16.29.09-.27s.02,0,0-.03v.03c-.04.06-.08.13-.12.21-.04.08-.09.16-.15.23,0,.02-.02.03-.04.02-.02,0-.03,0-.03,0v-.03c.04-.06.08-.13.12-.21.04-.08.06-.14.07-.18l.33-.75.12-.27s0-.02.01-.06c.03-.04.02-.06-.02-.07v-.06s.13-.24.13-.24c0-.04,0-.06-.02-.07v.03s-.06.09-.07.15l-.09.11s-.02.03-.04.02v-.03s.14-.3.14-.3v-.06s-.03.02-.03.02c0,.02-.02.03-.04.02l-.02.09.02-.09.46-1.05.11-.21v-.03s0,0-.03,0c0,0,0,.01,0,.03l-.19.45s-.03,0-.04.02v-.03s.01-.03.01-.03l.02-.09s-.04.05-.05.09l-.15.23s-.01,0-.03,0c0,0,0,.01,0,.03v-.06s.08-.15.08-.15l.13-.3v-.03s-.04.06-.04.06v-.06s.22-.48.22-.48c.2-.5.36-.92.5-1.24l.47-1.27.16-.46c.01-.06,0-.1-.04-.11-.2,0-.51-.02-.93-.07-.13-.03-.3-.04-.51-.05l-1.31-.15c-.38-.04-.68-.06-.87-.06-.04,0-.1.01-.18.06-.29.13-.59.34-.89.63l-.15.07c-.18.14-.5.38-.95.74-.29.24-.49.42-.61.52-.02.02-.12.1-.29.27l-.04.06c0,.09-.04.14-.13.17l-.13.14-.33.29s-.03.06-.08.05c-.08.05-.11.07-.11.07-.16.12-.38.36-.68.74-.02.02-.07.08-.14.2l-.04.06v-.06s.04-.13.04-.13l.35-.55.02-.09s0-.1.06-.15c.02,0,.03,0,.03,0,0-.02,0-.03,0-.03.06-.07.13-.19.21-.35.03-.02.05-.07.06-.15.02-.08.05-.14.1-.17l.66-.64.09-.11-.14.07s-.09.05-.12.1c-.06.05-.1.09-.12.1-.16.14-.29.23-.39.28l-.09.11-.08.08s-.07,0-.07.02l-.02-.04c.05-.03.08-.05.08-.05.02,0,.03,0,.03,0,0-.02,0-.03,0-.03.01-.06.09-.16.22-.28.11-.11.17-.18.18-.22.07-.12.1-.17.1-.17.02,0,.03,0,.03,0-.02-.03-.02-.04-.02-.04-.02,0-.03,0-.04.02-.09.11-.22.24-.38.38l-.04.06c-.07.12-.13.2-.19.25-.06.05-.18.17-.37.35,0,.02,0,.03,0,.03-.02,0-.03,0-.03,0v-.03s.1-.11.1-.11c.04-.17.15-.33.33-.48.16-.14.27-.26.34-.35.04-.1.1-.16.17-.19h.03s0-.07.05-.08c.03-.02.05-.03.08-.05l.06-.12c.05-.03.08-.06.08-.08v-.03s-.02,0-.02,0l-.11.07c-.07.1-.14.14-.23.15-.04,0-.09.03-.16.13l-.07.02.04-.06c.03-.06.11-.14.22-.25.1-.04.23-.19.39-.44l.04-.06.04-.06-.07.02c-.13.08-.45.34-.99.77l-.04.02v-.06s.53-.41.53-.41l.1-.17-.06-.04s-.06,0-.11.04c0,.02,0,.04-.01.06-.02,0-.04,0-.07.02l.03-.13c.05-.03.11-.09.17-.16.08-.05.09-.09.03-.13h-.03s-.07.01-.07.01l.04-.06c.06-.07.12-.13.17-.16l.22-.25.27-.2.47-.36.32-.26.12-.1v-.06s-.06-.06-.04-.08c.03-.02.05-.03.08-.05l.04-.02.04-.02v.06s-.02.03-.02.03h.03s.05-.03.08-.04c.05-.01.09-.02.14-.04l.09-.11v-.03s-.05-.04-.05-.04c0,.02-.03.04-.08.05l-.06.12s-.02,0-.06-.01v-.03c.14-.12.22-.19.25-.21.03-.04.07-.07.12-.1.05-.03.09-.07.12-.1.05-.01.1-.05.16-.13.11-.13.19-.21.22-.25l-.02-.04s-.01,0-.03,0c0,0,0-.01,0-.03v-.06s.08-.02.08-.02l.22-.25.22-.12.85-.73.39-.28.43-.33.04-.02v-.06s-.02,0-.02.02l-.43.33-.18.09s-.02.03-.04.02v-.06s.18-.16.18-.16c0-.02,0-.03,0-.03.03-.02.03-.04.01-.06v-.03c.09-.07.16-.14.22-.22.08-.09.17-.17.25-.24.39-.31.59-.46.59-.46l.37-.35c.2-.22.4-.39.6-.52l.62-.62c.08-.07.17-.15.28-.23.11-.09.23-.2.37-.35l.62-.59c.28-.27.43-.42.46-.46.1-.07.2-.15.29-.27.17-.18.31-.3.41-.37.08-.07.18-.16.29-.27.11-.11.23-.24.35-.38.06-.1.17-.19.32-.29.15-.1.27-.17.34-.22l.15-.07c.05-.03.12-.04.2-.02.08.02.15.02.19,0,.18,0,.28,0,.33,0,.08.02.18.06.3.13.04.03.11.06.21.08.04,0,.09.02.16.03.06.01.1.03.12.06.02.03.04.04.09.05.06.03.14.07.24.12.12.05.22.1.29.16.05.08.15.17.3.29l.2.14.07.15c.08.04.12.08.14.13.04.03.07.05.09.05l.08.08.14.39v.06s-.16.07-.16.07c-.1.07-.17.15-.22.25-.04.17-.08.31-.13.43-.05.12-.09.22-.13.3l-.2.61-.31.82-.23.61c-.13.41-.25.73-.34.97-.04.1-.09.21-.14.33-.04.1-.09.2-.13.3-.01.06-.04.12-.07.18-.03.04-.05.09-.07.15l-.1.17c-.09.11-.15.18-.17.19l-.04.06c-.09.11-.17.33-.24.67,0,.02.01.04.06.04l.09.02h-.1s-.02.04-.04.04c-.02,0-.03,0-.04.02,0,.04,0,.06.02.07.05-.01.07-.02.07-.02h.03s0,.04,0,.04l-.04.02.06.04s.11,0,.19,0h.06s-.03.02-.04.04h-.16s-.04.02-.04.02h.03s.37.12.37.12l.16.03s.04,0,.06.01c.04,0,.07.03.09.05.02.03.07.05.15.07l.41.06h.06s-.07.03-.07.03c-.13.01-.24.01-.33,0-.02,0-.03,0-.04.02h.03s.16.04.16.04l.02.04h-.03s-.1,0-.16,0l-.55-.02s0,.01,0,.03c0,0-.01,0-.03,0h.03s.66.12.66.12c.12.03.22.04.29.03l.06.04h-.06s-.39-.03-.39-.03c-.02,0-.1.01-.24.05-.13.01-.25.01-.36-.01-.05.01-.11,0-.19,0v.03s.21.08.21.08c.02,0,.03,0,.04-.02.05-.03.1-.03.13,0,.04,0,.07.02.09.02.02,0,.03.02.02.04h-.03s-.02.02-.04.02h.03s.03.02.02.04v.03s.03,0,.03,0c0-.02,0-.03,0-.03l.07-.02.51.05c.12.03.22.04.29.03l.03.04h-.03s-.02.02-.04.02h.03s.48.08.48.08l.21.08s-.03,0-.04.02c-.08-.04-.15-.05-.22-.05-.04,0-.07-.02-.09-.02-.07,0-.17,0-.32-.04-.06-.01-.12,0-.17.03h-.03s-.06-.02-.06-.02c-.06-.01-.12-.01-.16,0-.05.01-.09.01-.13,0l-.07.02s.03.02.03.04c.02,0,.03.02.02.04h-.03s-.03-.01-.03-.01h-.06s-.02.08-.02.08h.06s.26,0,.26,0c.04.03.09.04.16.03.07,0,.11,0,.13,0,.02,0,.03,0,.03,0h.06s-.03.04-.07.03c-.18,0-.33,0-.45-.03l-.11.04s-.03,0-.04.02h.03s.41.09.41.09l.09.05h.03s.41.06.41.06c.17.04.28.05.35.04l.29.03.45.03h.06s.06.06.06.06h-.06s-.52-.03-.52-.03h-.33s-.07.01-.07.01h.06s.19.02.19.02c.19.04.43.07.73.09.1.02.24.03.42.03l.51.05c.12.03.22.04.29.03.04,0,.04.02,0,.03,0,0,0,.01,0,.03,0,0,.01,0,.03,0,.02,0,.03,0,.04-.02l.69.12.99.12.25.05h.03s-.03.01-.04.03l-.26-.02h-.65s-.42-.04-.42-.04c-.08-.02-.16-.02-.22-.02-.28-.02-.49,0-.63.03h-.65s-.8-.09-.8-.09l-.68-.02-.65-.04-.55-.02-1.24-.04s-.1.02-.17.03c-.06-.01-.12-.01-.16,0-.04,0-.07,0-.08.05l-.14.36-.19.42c-.01.06-.05.11-.1.14,0,0-.01,0-.03,0,0,0,0,.01,0,.03v-.03s.08-.21.08-.21l.08-.21.05-.09.03-.13-.11.07v-.03s-.01-.07,0-.13v-.03s-.03.02-.03.02l-.07.18c-.04.1-.09.24-.13.43-.02.02-.04.03-.04.06.02,0,.04,0,.07-.02.02,0,.02.01,0,.03l-.08.05c-.06.05-.1.13-.15.23-.02.08-.03.15-.04.19-.08.35-.15.61-.23.77l-.4.96c-.04.1-.14.32-.31.65-.06.16-.12.31-.19.45-.07.12-.12.22-.17.32-.14.34-.28.63-.42.86-.14.23-.23.42-.29.56-.08.16-.12.28-.14.36,0,.04-.01.06-.01.06,0,.07-.02.14-.08.21l-.16.29-.24.37c-.01.06-.03.11-.06.15-.18.33-.27.51-.28.53-.03.02-.05.06-.06.12l-.06.12c-.09.22-.17.37-.23.44-.09.2-.14.35-.16.46l-.23.61c-.02.08-.05.16-.08.24-.04.08-.07.15-.08.21,0,.04-.05.11-.11.21-.05.12-.07.24-.07.34v.03s-.07,0-.08.02c0,.04-.02.07-.02.09-.06.07-.1.14-.11.21h-.03s0-.04,0-.04ZM106.35,28.39l.09-.11v-.03s-.03,0-.03.02c-.05.03-.08.06-.08.08v.03s.03,0,.03,0ZM112.14,36.62s-.03-.04-.01-.1l.06-.12h.03c-.01.07-.03.11-.06.13l-.02.09ZM111.81,33.89s0-.03,0-.03c.02,0,.03,0,.03,0,.02-.08.06-.16.12-.24v-.06s.02-.03.02-.03l-.04.02-.13.3v.03ZM112.03,34.1s.06,0,.11-.04c-.02,0-.03-.02-.02-.04,0-.02,0-.03,0-.03-.04,0-.07.02-.08.08v.03ZM112.32,34.86c.05-.03.08-.05.08-.05l.02-.09-.08.08v.06ZM112.17,33.87l.04-.06c.01-.06.04-.11.07-.15h.03s0,.04,0,.04c0-.02,0-.03,0-.03.02,0,.03,0,.03,0l.02-.23v-.03s-.03,0-.03.02c-.07.12-.11.22-.13.3-.03.02-.04.06-.06.12,0,0,0,.02-.01.06l.04-.06ZM112.21,33.1s0-.03-.03-.04v.03s-.05.07-.07.15c-.03.04-.05.09-.07.15l.16-.29ZM112.72,34.06s.05-.06.06-.12h.03c.02-.08.02-.14,0-.19v-.03s0,.03,0,.03l-.13.3h.03ZM112.46,33.31c.06-.07.1-.14.11-.21.04-.06.06-.11.07-.15l.02-.09v-.03s-.03,0-.03.02v.03c-.08.05-.12.11-.11.17l-.05.09c-.05.03-.08.08-.1.14l.02.07.08-.05ZM112.38,32.15s.04-.03.04-.06c0-.04.03-.07.05-.09v-.06s-.03.06-.03.06l-.04.06-.02.09v.03s0-.03,0-.03ZM112.75,32.72v-.03c.02-.06.04-.11.07-.15l-.03-.04v.03s-.1.11-.1.11c-.05.01-.06.03-.04.06.02.03.02.05.02.07h.03s.04-.05.04-.05ZM112.89,32.36l.04-.06c.02-.08.06-.18.13-.3v-.03s.01-.03.01-.03h-.03s-.19.41-.19.41l.03.04v-.03ZM112.64,31.55s.03,0,.04-.02l.05-.09.03-.13v-.06s-.03.06-.03.06c-.02.1-.05.17-.08.21v.03ZM109.73,25.19s.06,0,.07-.02c.03-.02.04-.03.04-.06.04,0,.07,0,.1-.01.03-.02.04-.03.04-.06.03-.04.08-.07.15-.1.07-.03.12-.06.15-.1.05-.03.08-.08.1-.14.03-.02.04-.05.05-.09h.03s0,.05-.01.07c.02,0,.03,0,.04-.02.05-.01.08-.05.09-.11.03-.06.06-.1.09-.11,0,0,0-.01,0-.03,0-.02,0-.03-.02-.04-.02,0-.04,0-.07.02,0,.02-.01,0-.02-.04v.06s-.05.07-.11.14c-.05.01-.08.04-.11.07-.03.04-.06.06-.08.08-.02,0-.04.01-.04.06.02,0,.03,0,.04-.02l.02.04s-.03.06-.08.05c-.04-.03-.08-.03-.13,0-.08.05-.11.07-.11.07.01.05,0,.09-.03.13-.03.04-.06.06-.08.08,0-.04,0-.08-.01-.1l-.14.17h.03ZM113.02,31.34s0-.03,0-.03c.02,0,.03,0,.03,0,.02-.08.06-.18.13-.3v-.06s0-.1,0-.1l-.05.09s-.02.05-.05.09c0,.02,0,.05.01.1l-.07.18v.03ZM113.19,31.74l.19-.42v-.03s.02-.06.02-.06l-.04.06-.07.15-.13.3v.03s.03-.02.03-.02ZM110.82,24.38s.03-.07.05-.09v-.06s-.02.02-.02.02c-.05.03-.08.07-.09.11l-.02.09.08-.08ZM113.48,31.01s0-.03,0-.03c.03-.02.04-.03.05-.06.07-.12.11-.21.12-.27.07-.12.11-.21.12-.27v-.03s0,.01,0,.03c0,0-.01,0-.03,0v.06s-.18.29-.18.29v.03s0-.03,0-.03l.05-.09-.02-.07v.03s-.06.09-.07.15c0,.04-.04.08-.09.11l-.02.09s.01.04.06.04ZM111.07,24.14c.09,0,.14-.03.15-.07v-.03s0-.03-.02-.04c-.1.07-.15.1-.15.1v.03s.03,0,.03,0ZM113.34,30.16l.06-.12.09-.27v-.03s-.03.02-.03.02l-.15.39v.03s.03-.02.03-.02ZM113.37,29.88c.08-.16.13-.28.14-.36v-.03s0,.03,0,.03l-.1.17-.07.15v.03s.03,0,.03,0ZM111.27,23.53v-.03c-.09.04-.15.09-.18.12v.03s.18-.12.18-.12ZM111.35,24.07v-.06s.1-.11.1-.11c0,0,0-.02.01-.06l-.13.14v.06s-.06.06-.06.06l.07-.02ZM113.55,29.62l.04-.02v-.06s.03-.06.03-.06c0,.02-.02.03-.04.02l-.06.12.02.07v-.06ZM113.51,29.35v-.06s.03-.06.03-.06c0-.02,0-.03,0-.03.02,0,.03,0,.03,0l-.02-.04s0,.01,0,.03c0,0-.01,0-.03,0l-.02.09v.06s.02,0,.02,0ZM113.64,29.81c.01-.06.03-.11.06-.15l.04-.02h.03s0-.02,0-.02l-.02-.04-.03-.04v.03s-.12.21-.12.21v.03s-.01.03-.01.03l.04-.02ZM111.34,23.48l.12-.1v-.03s-.03,0-.03,0l-.12.1v.03s.03,0,.03,0ZM111.54,23.92s.03-.05.08-.08l.02-.09c-.08.05-.11.07-.11.07,0,.04,0,.08.01.1ZM111.55,23.72s0,.03,0,.03c.02,0,.03,0,.04-.02l.15-.07-.02-.04s0-.02-.03,0l-.11.07v.03ZM112.59,26.17s.06-.02.1-.01h.06s.07,0,.07,0h-.06s-.06-.03-.06-.03c-.06-.01-.1,0-.11.04-.04-.03-.1-.05-.18-.07h-.06s.06.03.06.03l.19.04ZM113.85,29.46s.03,0,.04-.02v-.03s.01-.03.01-.03l-.02-.07s-.01,0-.04.02c0,0-.01,0-.04.02v.03s.03,0,.03,0l.04-.02v.03s-.01.03-.01.03v.03ZM114,29.82s.03,0,.03,0c0-.02,0-.03,0-.03.03-.04.05-.09.07-.15v-.03s-.03.02-.03.02l-.06.12v.06ZM111.76,23.67c.05-.03.08-.06.08-.08l.03-.13c-.05.03-.08.06-.08.08l-.03.13ZM112.03,23.5s.04-.02.11-.07c-.05-.06-.08-.09-.07-.11-.05.03-.08.05-.08.05-.03.02-.04.03-.05.06,0,.02,0,.04.02.07l.02.07.04-.06ZM114.13,29.52s.02-.03.04-.02c.02,0,.03,0,.04-.02l.12-.24.04-.19-.02-.04v.03c-.03.1-.06.17-.09.21v.03c-.02.06-.05.12-.11.17v.06ZM114.12,28.8s0-.03-.02-.04l-.07.02.02.07.08-.05ZM112.18,23.4c.05-.03.08-.05.08-.05l-.03-.04s-.07,0-.07.02l.02.07ZM111.9,23.34l.17-.16.3-.2v-.03s-.02,0-.02,0l-.28.23-.2.15v.03s.03-.02.03-.02ZM112.3,23.29s.08-.05.08-.05c.05-.01.1-.07.17-.16l.13-.14.13-.14s.03,0,.04-.02h-.03s-.06.02-.11.04c-.05.01-.07.05-.06.12-.05.03-.09.05-.11.04-.02,0-.04,0-.07.02-.02.02-.04.03-.04.06-.02.08-.05.12-.09.11-.03.02-.04.05-.05.09l.03.04ZM112.61,22.48l.08-.05s-.03-.02-.02-.04l-.12.1v.03s.07-.05.07-.05ZM112.77,22.64l.16-.13v-.03s-.03,0-.03,0l-.13.17s-.09,0-.14.04c-.05.03-.08.07-.09.11h.03s.2-.15.2-.15ZM112.98,22.72l.13-.17v-.03s-.02,0-.02,0l-.16.13-.03.13.08-.05ZM112.88,25.32s.03.02.03.04c.02,0,.04,0,.07-.02l.74.06.69.15c.07-.03.11-.05.11-.07l.02-.09.22-.74.13-.43c.03-.06.06-.13.08-.21l.03-.13c-.05.03-.08.05-.08.05v.03s-.87.66-.87.66c-.1.07-.17.1-.22.12-.07,0-.15.04-.25.11l-.21.22c-.06.07-.11.13-.17.16-.06-.03-.11-.04-.16,0-.03.02-.06.03-.11.04,0,.04-.02.06-.05.06ZM113.41,22.39s.03,0,.03,0c0-.02,0-.03,0-.03.05-.03.08-.06.08-.08.05-.03.11-.09.17-.16v-.06s.03-.06.03-.06l-.04.06-.04.06s-.05.04-.08.08c0,.02-.03.03-.07.02v.03s-.03.07-.06.09v.03s-.01.03-.01.03ZM115,25.51s.07-.03.08-.05l.03-.16.04-.06s-.06.02-.1.01l-.06.12v.06s0,.07,0,.07ZM114.89,25.39l.23-.44s0-.03-.02-.04v.03s-.12.24-.12.24c-.02.08-.04.15-.08.21v.03s0-.03,0-.03ZM113.82,22.02l.12-.1-.02-.07h-.03s-.04.06-.1.14v.06s.02-.02.02-.02ZM115.13,25.51s.03-.01.04-.06c.04-.08.07-.18.1-.31v-.06s-.02.02-.02.02l-.12.4-.02.09.02-.09ZM115.13,25.21l.09-.11-.02-.07-.05.06s-.07.04-.08.08v.03s.06.01.06.01ZM115.36,25.66s.06,0,.07-.02c.02,0,.02,0,0-.03,0-.02,0-.03,0-.03-.04-.03-.03-.08.03-.16,0-.02.01-.02.03,0h.03s0-.03-.03-.03c-.03-.07-.02-.12.03-.16v-.06s-.01-.04-.01-.04v.03s-.05.05-.06.09c0,.02-.02.04-.05.06l-.06.28v.06ZM115.8,24.67s.01-.06.01-.06c0-.02-.01-.04-.06-.04,0-.02,0-.02-.03,0l.06.04.02.07v.06s0-.06,0-.06ZM116.19,25.58l.06-.12v-.06s-.06.05-.06.05c0,.02-.02.04-.04.06,0,.02,0,.04.02.07,0,.04,0,.06.02.07v-.06ZM115.58,24s.03-.03,0-.03l.13-.3s-.01,0-.03,0c0,0,0-.01,0-.03v.03c-.04.06-.07.15-.1.27v.06ZM116.14,24.91l.05-.06s0-.03-.03-.04c0-.02,0-.04.01-.06v.06s-.06.05-.07.09l.02.07v-.06ZM117.67,25.24s0-.03,0-.03c.02,0,.03,0,.03,0,.09-.11.14-.19.15-.23l.13-.59v-.03s0,.03,0,.03l-.25.7-.06.12v.03ZM119.79,27.43c.09-.02.16-.03.2-.02.03-.02.04-.01.03,0,.02,0,.04,0,.06.01l.06.04h-.06c-.08-.03-.15-.03-.19-.02l-.09-.02ZM121.14,18c-.1-.02-.23-.09-.38-.21-.17-.12-.33-.32-.49-.6-.1-.22-.3-.47-.59-.75l-.48-.5c-.17-.21-.27-.32-.29-.32l-.59-.62-.52-.6-.5-.57c-.05-.08-.31-.33-.78-.76l-.35-.37c-.03-.05-.12-.14-.27-.26-.19-.13-.32-.23-.39-.31-.14-.14-.26-.27-.34-.4l-.24-.25c-.09-.19-.14-.35-.16-.46-.02-.03-.02-.06-.01-.1.01-.06.02-.1.03-.13.1.02.19,0,.25-.08-.03.06-.03.11,0,.16.04.03.06.04.06.04l.07-.02v.06s.08,0,.1-.07c.04.03.06.07.07.11.03.05.07.08.11.09-.03-.07-.07-.14-.12-.19l.04-.02c.1.15.2.24.3.26l-.21-.24s.03-.02.08-.05c0-.04,0-.07-.05-.08l-.19-.04c-.06.05-.09.08-.11.07-.02-.03-.04-.06-.07-.11.1.04.18.02.25-.08-.06-.01-.11-.04-.15-.07l-.06.12h-.03s-.01-.11-.01-.11h-.03s-.02.09-.02.09c-.05.03-.09.05-.11.04-.02-.03-.02-.05-.02-.07,0-.02,0-.03-.02-.04-.04-.03-.06-.02-.07.02.01.05,0,.07-.01.06v-.03s0-.12.02-.23l.08-.05s.06,0,.11-.04l.22.18.09-.11s0-.08-.01-.1c-.01-.05-.03-.07-.05-.08-.02,0-.07-.02-.16-.03-.06-.01-.12,0-.17.03.01-.06.04-.11.07-.15-.02,0-.05-.03-.08-.08l.31-.2-.06-.04s.06-.02.1-.01l.11-.07.07-.02c.14-.06.22-.13.24-.21.03-.06.1-.1.19-.12.05-.01.1-.01.16,0,.17.04.29.12.37.24,0,.02,0,.03,0,.03.02,0,.03,0,.03,0,.12.07.23.16.33.27.13.11.23.2.3.26.2.17.46.47.76.88l.35.37.29.32.13.16.33.3c.05.06.11.11.16.17.08.04.15.1.22.18l.43.42c.18.17.32.31.4.41l.56.61c.14.16.35.42.62.79l.35.37c.07.1.17.23.31.39.17.21.46.49.87.84l.3.29c.11.18.18.3.18.37.01.05.02.1.03.17.01.05,0,.11,0,.19v.03s-.08.12-.19.22c-.15.08-.33.15-.54.21-.18.05-.32.08-.42.11-.14.04-.34.07-.61.1h-.36s-.09-.03-.09-.03ZM115.41,11.3c-.03-.16-.1-.23-.22-.21l.22.21ZM116.39,12.52l-.22-.21.21.24v-.03ZM116,11.75h-.06s-.03-.02-.03-.02v-.06s-.26-.22-.26-.22v.03c.04.08.14.17.29.29,0,.02.01.04.06.04v-.06ZM116.68,12.88s.02-.03.04-.02c-.11-.09-.2-.19-.26-.29v.03c.04.08.12.17.23.28ZM116.06,11.8c-.01.06.01.13.08.21.09.09.16.12.2.11l-.29-.32ZM116.5,12.35s.03,0,.04-.02c-.02,0-.05-.02-.09-.05-.01-.05-.05-.07-.12-.06l.17.13ZM116.02,11.53c-.03-.05-.09-.11-.16-.17.03.05.09.11.16.17ZM116.79,12.64l-.11-.09v.03s.1.12.1.12v-.06ZM115.61,10.69s-.08-.05-.12-.06c-.04,0-.08,0-.11.04l.09.02s.02.03.05.08l.08-.08ZM115.64,10.4v.06c-.03.08.02.16.13.23l-.13-.29ZM117.73,13.63c-.03-.05-.09-.11-.16-.17.02.09.08.15.16.17ZM116.89,12.17l-.45-.49v.03s.41.48.41.48l.04-.02ZM116.08,10.79s0-.03,0-.03c.02,0,.03,0,.03,0l-.07-.11s-.07-.03-.09-.05c-.01-.05,0-.09.03-.13.05.08.15.17.3.29,0,.02.01.04.06.04v-.03s0-.04-.05-.04l-.07-.11s-.04-.04-.02-.04c.05-.01.07-.03.08-.05l.04-.06c-.11-.02-.18-.03-.23-.02-.06-.01-.1-.03-.12-.06h-.06s-.09.1-.09.1h-.03s.3.29.3.29ZM117.07,11.66c-.08-.06-.13-.11-.16-.17-.03-.05-.07-.09-.11-.12l-.16-.03.02-.09-.19-.17h-.06c.11.1.19.19.23.27.04,0,.07.03.09.05l.06.04c.07.1.12.17.15.2l.11.09v-.06ZM116.83,11.28c-.03-.07-.1-.15-.21-.24-.11-.11-.19-.16-.26-.15l.47.4ZM117.92,12.89l-.37-.41c-.11-.11-.19-.18-.25-.22.28.32.49.55.64.69l-.02-.07ZM117.35,12.04c-.02-.09-.07-.15-.13-.16v-.06s-.02,0-.02,0c0,.02-.02.04-.04.06,0,0,0,.01.02.04,0,.07.06.11.17.13ZM117.54,12.22l-.1-.12s0,.01,0,.03c0,0-.01,0-.03,0,0,.02.04.06.14.13v-.03ZM117.24,11.66l-.19-.17c-.03-.05-.06-.08-.08-.08l-.08-.08c.03.07.09.17.2.3.12.14.22.22.3.26l-.15-.23ZM116.53,10.52l-.09-.02h-.03s.1.11.1.11l.02-.09ZM118.01,12.77c-.03-.07-.07-.11-.14-.13v.03s.13.13.13.13v-.03ZM117.72,12.29c-.08-.13-.15-.21-.21-.24,0,0,0,.01,0,.03,0,0-.01,0-.03,0l.24.25v-.03ZM118.62,13.56c-.06-.03-.14-.11-.25-.22v.03c.03.05.06.09.1.12.04.03.08.06.11.09l.04-.02ZM118.01,12.61c0-.07-.04-.1-.11-.09.03.05.07.08.11.09ZM118.2,12.82s-.03-.05-.1-.15l-.04.02c.06.1.1.15.1.15l.04-.02ZM119.07,14.08s0-.03,0-.03c.02,0,.03,0,.03,0l-.22-.21v.03s.18.2.18.2ZM118.7,13.51s.03,0,.03,0c0-.02,0-.03-.02-.04l-.1-.12.07.15h.03ZM118.88,13.45l-.62-.62s-.03,0-.04.02c.08.13.19.25.31.36.13.11.23.2.3.26l.04-.02ZM119.08,13.86c-.03-.05-.07-.08-.11-.09-.02-.03-.04-.03-.06-.01.02,0,.04.03.05.08.04.03.08.04.12.03ZM119.06,13.69c-.06-.1-.13-.16-.19-.17.03.05.09.11.16.17h.03ZM119.91,14.56c-.12-.16-.24-.29-.37-.41-.11-.11-.21-.22-.32-.33-.02,0-.03,0-.04.02.41.42.64.65.7.71h.03ZM119.55,14.29l-.2-.14c.07.1.13.16.19.17v-.03ZM120.19,14.82c-.06-.03-.11-.07-.14-.1-.02-.03-.03-.05-.05-.08.06.12.12.18.19.17ZM130.14,39.46c-.19-.13-.34-.21-.44-.26-.07-.06-.16-.12-.25-.19-.07-.06-.15-.12-.22-.18-.19-.13-.32-.24-.38-.34-.19-.13-.35-.29-.48-.5-.13-.12-.2-.28-.22-.51.02-.08.02-.16.02-.23,0-.07-.02-.12-.03-.17l.08-.67c0-.09.02-.25.07-.48l.16-.75c.06-.18.14-.48.23-.9l.13-.59.09-.27.03-.16c.04-.1.09-.25.13-.46.02-.1.05-.23.08-.38.06-.16.13-.34.21-.54l.21-.81c.05-.14.11-.35.17-.62.05-.14.11-.36.17-.65.04-.1.09-.24.13-.43l.17-.62.17-.62.14-.49.15-.56c.03-.13.06-.24.1-.34.05-.12.09-.24.11-.37,0-.15.03-.28.05-.38.05-.12.08-.22.1-.31.05-.14.12-.38.19-.71l.25-.86.14-.49c.04-.21.09-.36.13-.46,0-.04.01-.11,0-.19.02-.1.05-.19.08-.24,0,0,0-.02-.02-.07,0-.04.03-.05.07-.02l.06-.12s0-.03-.02-.04c.05-.01.08-.05.09-.11.04-.06.05-.1.06-.12v-.03s0,.03,0,.03c.01.05,0,.12-.02.23v.03s.02,0,.02,0c0-.02,0-.03,0-.03l.03-.16v-.03s.04.02.03.04l-.06.28-.09.11s-.03.07-.05.09l.02.07s.02-.06.04-.06c0-.02,0-.03,0-.03.02,0,.03,0,.03,0l.05.04-.04.19c0,.09-.01.17-.05.25-.02.08-.03.17-.02.26l-.07.15v.03s.01.07,0,.13l-.09.24-.02.09c-.01.06-.01.11,0,.13-.03.04-.05.09-.07.15,0,.07,0,.12-.03.16,0,.02-.02.05-.05.09,0,.02,0,.06,0,.13,0,.04-.03.1-.07.18-.03.06-.04.11,0,.16.02,0,.03.02.02.04-.09.09-.12.17-.12.24.03.05.06.08.08.08l.04-.06c0-.13.02-.24.04-.32.04-.08.06-.14.07-.18,0-.07,0-.12,0-.16.04-.06.06-.11.07-.15l-.02-.07v-.03s.06-.09.07-.15c.02-.08.04-.14.07-.18.01-.06.02-.13,0-.19.01-.06.04-.13.08-.21v-.26s.04-.09.04-.09c.02-.1.05-.18.08-.21v-.03s.04,0,.04,0c.02.03.02.07,0,.13h.03s.03,0,.04-.02l-.02.09-.04.06h.03s.02.04.02.04c0-.02,0-.03,0-.03l.19-.45.04-.06s0,.03,0,.03c.02,0,.03,0,.03,0l-.02.09s-.05.04-.02.09v.06s-.06.06-.06.06v.03s.03,0,.03-.02c.1-.04.15-.12.15-.23.02-.1.04-.19.05-.25-.04-.03-.04-.07,0-.13.04-.06.06-.11.07-.15-.03-.05-.06-.08-.08-.08v-.03s.04,0,.04,0c.04,0,.06,0,.04-.06-.02,0-.03,0-.03,0,0-.02.02-.03.04-.02l.04-.06c.03-.06.07-.15.09-.27.02-.1.03-.19.02-.26l.15-.56v-.06s.03.07.03.07l-.07.31c-.03.06-.06.14-.08.24,0,.11-.01.19-.02.26l-.1.44c0,.13-.04.33-.1.6.02,0,.03.02.03.04v-.06s.06-.05.07-.09l-.02.09c0,.07,0,.15-.02.26v.06s-.03-.07-.03-.07v-.06s0-.03-.01-.04v.03s-.11.31-.11.31l.02.04s.05.06.04.14c0,.09-.01.2-.04.35-.03.13-.04.23-.04.32.02.03.01.05-.01.06,0,.02,0,.04-.01.06l.02.04.04-.02c.05-.25.1-.44.15-.56l.1-.47.07-.18s0-.04.01-.06c0-.04.03-.07.05-.09l.04-.02c-.06-.03-.08-.07-.07-.11.03-.04.05-.07.05-.09,0-.07,0-.12,0-.16.03-.04.05-.08.06-.12l.05-.22.03-.13s-.01-.1,0-.16c.03-.06.06-.11.07-.15v-.03s0,.03,0,.03v.36s0,.07,0,.07l.04-.06c.06-.05.1-.15.13-.3l.03-.29s0-.01,0-.03c0-.04.04-.06.08-.05.02,0,.04,0,.07-.02.03-.02.04-.03.04-.06.09-.2.12-.37.11-.5l.09-.11.02.04s.03.02.02.04c-.03.04-.05.1-.07.18,0,.02,0,.03,0,.03.02,0,.03,0,.03,0,.07-.03.11-.07.13-.14.04-.06.05-.1.06-.12l.07-.34s.02-.03.04-.02v.03s-.04.16-.04.16l.02.04.04-.02c.01-.06.03-.1.06-.12-.02,0-.03,0-.03,0,0-.02,0-.03,0-.03l.14-.2s.03,0,.03,0c0-.02,0-.03,0-.03.04,0,.06.02.06.04-.03.02-.04.05-.05.09.01.05,0,.08-.02.09l-.02.09s-.05.08-.06.12c.01.05,0,.08-.02.09-.06.1-.11.21-.14.33-.02.1-.04.18-.05.22l-.13.46s-.02.09-.03.16c0,.07,0,.14-.05.22l-.03.13s.01.06.04.11c0-.04.03-.07.05-.09l.24-.8c.06-.29.12-.5.17-.62l.07-.31c.01-.06.04-.12.07-.18.04-.08.07-.14.1-.17.04-.08.1-.16.19-.25.09-.09.15-.17.18-.22.13-.21.22-.35.25-.4l.04-.06-.04.06v.1c.06-.03.09-.05.09-.05.03-.02.05-.03.08-.05.03-.02.04-.03.04-.06,0-.02,0-.03,0-.03.02,0,.03,0,.03,0v.03s-.1.14-.1.14c-.04.1-.1.23-.18.39-.07.14-.14.31-.21.51-.08.16-.15.34-.22.54-.07.2-.11.35-.12.43l-.03.13c-.03.15-.07.26-.1.34-.05.23-.1.4-.15.53-.02.08-.04.18-.06.28,0,.11-.03.23-.08.38l-.09.73-.1.47c-.02.08-.03.2-.04.35,0,.13-.03.24-.07.34-.01.15-.04.28-.08.38-.02.1-.04.2-.06.28,0,.07,0,.15-.05.25-.02.1-.04.19-.05.25l-.17.78-.11.5c-.06.16-.11.36-.16.59-.03.23-.06.4-.08.51l-.2.78c-.03.15-.08.32-.15.53-.04.21-.09.45-.12.73-.04.1-.08.23-.12.4,0,.15-.02.26-.04.32l-.23.77v.06s0,.07,0,.07l.04-.02s.1-.06.16-.13c.08-.07.18-.18.3-.33.06-.1.13-.18.19-.25.08-.07.15-.14.21-.22l.33-.32.7-.83c.08-.07.25-.25.51-.54.03-.06.13-.14.28-.23v-.06s.44-.46.44-.46c.03-.06.07-.11.1-.14.06-.05.1-.11.13-.17.14-.12.25-.23.33-.32.09-.11.18-.21.26-.3.06-.07.15-.18.26-.3.14-.14.26-.26.37-.35.06-.1.18-.23.35-.42l.3-.33c.11-.09.25-.24.43-.46-.03.04.12-.13.47-.49l.53-.51s0-.03,0-.03c.02,0,.03,0,.03,0,.02,0,.03.02.02.04l-.03.13s-.04.02-.04.02c.02,0,.03,0,.03,0,.02,0,.03,0,.03,0,0-.02,0-.03,0-.03v.03s-.02.06-.02.06l.07-.02.51-.54s0-.03,0-.03c.02,0,.03,0,.03,0v.03s-.07.07-.1.11c-.03.02-.04.05-.05.09-.05.03-.08.07-.09.11.03.07.01.15-.05.25v.03s.03,0,.03-.02c.02,0,.03,0,.03,0,0-.02,0-.03,0-.03l.04-.06v.06s-.02.03-.02.03l.04-.02.14-.2.19-.12s0-.02,0,0c.02,0,.03,0,.03,0v.06c-.11.04-.19.14-.27.27l-.44.69-.17.16v.03s-.02.06-.1.11c0,.04-.04.08-.09.11l-.04.06s-.02.03-.04.02l.05.04.11-.04.46-.62.18-.22s.02-.03.04-.02v.06s-.18.32-.18.32l-.42.6c-.11.09-.18.19-.23.31,0,.02-.02.03-.04.02v.06s.02.03.05.01c.04,0,.09-.03.16-.13.06-.05.11-.12.17-.19.08-.07.16-.15.25-.24.1-.15.21-.27.34-.35l.26-.3c.1-.07.17-.12.2-.15.02,0,.02,0,0-.03,0-.02.02-.03.04-.02,0-.04.04-.08.09-.11l.22-.12.15-.1.2-.19.4-.47.07-.02v.06s-.05.03-.06.06c0,.02-.03.04-.08.05,0,0-.01.02-.04.06,0,.02.01.04.05.04v.03s-.02.03-.04.02h.06s.03,0,.04-.01l.02.07s0,.03,0,.03c.03.05.02.12-.05.22v.03s0-.03,0-.03c.02,0,.03,0,.03,0,.12-.06.2-.1.22-.12.02,0,.04,0,.07-.02.05-.03.08-.06.08-.08.18-.14.34-.29.46-.46,0,0,.03-.02.08-.05.04,0,.11-.02.21-.08.08-.05.13-.06.17-.03.14-.06.26-.12.34-.19.08-.09.25-.2.49-.32.05-.03.11-.09.17-.16.02,0,.03,0,.03,0,0-.02,0-.03,0-.03v.03s-.1.14-.1.14c-.24.19-.4.34-.49.45-.16.14-.31.28-.45.43-.14.12-.29.26-.45.39-.18.22-.32.39-.43.5-.05.05-.11.13-.18.22-.06.07-.13.16-.22.25-.03.06-.1.15-.19.29-.07.12-.14.21-.22.28-.1.15-.21.29-.32.42-.09.11-.18.22-.27.33-.18.22-.3.39-.37.51l-.15.26c-.01.06-.04.11-.1.14-.1.15-.21.28-.35.38-.14.23-.26.4-.37.51l-.45.56c-.18.22-.35.43-.52.61-.14.17-.27.31-.39.44l-.55.73-.38.38-.43.46c-.19.26-.35.46-.49.58-.09.11-.18.21-.26.3-.09.09-.16.17-.22.25-.06.07-.13.16-.22.25-.07.1-.13.19-.19.29-.06.1-.18.21-.34.35-.12.13-.25.28-.4.47-.13.19-.28.4-.46.62-.15.19-.26.34-.33.45-.08.07-.18.18-.3.33-.46.6-.73.96-.82,1.07-.04.08-.09.15-.14.2-.06.05-.1.12-.14.2-.03.06-.09.15-.15.26-.07.12-.1.23-.1.34l-.02.09-.1.31s-.02.06-.04.06c-.06-.01-.13.04-.2.15v.06c-.1.11-.24.17-.41.18-.12-.03-.21,0-.25.08-.05.05-.11.07-.18.06-.06-.01-.1-.02-.13-.03h-.06ZM129.93,31.03s0-.04.01-.06c.03-.02.03-.04.01-.06l-.06.12v.06s.03-.06.03-.06ZM130.11,31.27v-.03s.02-.06.02-.06l-.04.06s0,.01,0,.03c0,0-.01,0-.03,0,.02.03.02.06.01.1h.03s.02-.09.02-.09ZM130.18,31.09s-.02-.05-.02-.07c.03-.04.04-.06.04-.06-.05.03-.08.06-.08.08-.02-.03-.03-.03-.03,0,.02.03.03.04.03.04h.06ZM130.32,29.54s.02-.03.04-.02c-.02-.03-.02-.06-.01-.1-.02,0-.03,0-.04.02,0,.04,0,.08.01.1ZM130.45,29.08s.03,0,.04-.02h.03s-.06-.04-.06-.04c0,0,0,0-.03,0,0,0,0,.01,0,.03l-.02.09.04-.06ZM131.03,29.76l-.02-.04-.04.02-.04.06.02.07.09-.11ZM130.69,29.04l.03-.13s0,0-.03,0c0,0,0-.01,0-.03v.06s-.05.01-.06.06v.1s.06-.06.06-.06ZM130.56,28.58v-.06s-.02,0-.02.02c-.02.02-.03.06-.03.13l.05-.09ZM130.59,28.46c.02-.08.04-.15.08-.21,0,0-.01,0-.03,0,0,0,0-.01,0-.03,0,.02-.02.03-.04.02v.03s-.05.19-.05.19h.03ZM131.49,29.31s0-.08-.01-.1l-.04.06s0,.08.01.1l.04-.06ZM130.69,27.99l.04-.02h.03s-.02-.06,0-.13c0-.02,0-.03-.02-.04v.03c-.02.06-.04.11-.07.15,0,.04,0,.08.01.1l.02-.09ZM130.87,28.39v-.03s.05-.19.05-.19l.02-.09h-.03s-.05.08-.05.08l-.05.22v.06s.06-.05.06-.05ZM131.02,27.99l-.02-.07h-.03s-.01,0-.03-.01c0,0,0,.01,0,.03l.02.07.07-.02ZM130.82,27.56c.02-.08.05-.13.1-.14l.04-.02s-.1,0-.18.06c0,.04,0,.08.01.1,0,0,0,.01,0,.03,0,0,.01,0,.03,0v-.03ZM130.98,27.85s.04-.01.04-.06l.04-.06-.04-.11s.03-.04.01-.06c0-.02.02-.04.04-.06.02-.02.03-.03,0-.03-.02,0-.03-.02-.02-.04-.05.01-.07.04-.08.08l.02.07s-.03.03,0,.03c.02,0,.03,0,.03,0,0,.02-.04.07-.1.14,0,.02,0,.03.02.04.02,0,.03.02.02.04ZM131.4,28.04s.02-.02.08-.05c-.02,0-.03,0-.03,0,0-.02,0-.03,0-.03,0,0-.02.02-.08.05l.02.04ZM130.96,27.03s.02,0,0,0c0-.02,0-.03,0-.03v-.03s.03-.13.03-.13c.06.03.09.02.11-.04l.02-.09s0-.03-.02-.04v.03s-.02.06-.02.06c0,.02-.02.04-.04.06-.02,0-.03,0-.04.02v-.03s.06-.09.07-.15l-.06-.04v.03s-.11.34-.11.34c-.01.06-.01.11,0,.13l.05-.09ZM131.19,27.18v-.13s0-.03,0-.03c.05-.03.06-.07.03-.13l.04-.06s.02-.03-.02-.04c-.02,0-.06.02-.11.07l.02.2h-.03s.01.09.01.09l.02.07.04-.06ZM131.06,26.59s.02-.03.04-.02c-.02-.03-.02-.06-.01-.1-.02,0-.03,0-.04.02,0,.04,0,.08.01.1ZM131.34,26.65l-.02-.07-.07.02c-.01.06-.01.12,0,.16l.09-.11ZM131.63,26.95s.07-.04.08-.08l-.02-.07h-.03s-.01.06-.01.06c0,.04-.03.07-.05.09v.03s0,.01-.01.03c.02,0,.03,0,.04-.02v-.03ZM131.1,26.37s.07,0,.08-.05c.06-.07.07-.14.04-.19-.02,0-.03-.04-.01-.1.05-.01.06-.03.04-.06,0-.04.01-.06.01-.06,0-.04,0-.06-.02-.07.03-.02.03-.03,0-.03,0-.02,0-.04.01-.06l-.04-.14-.04.06s.01.1,0,.16c-.01.06-.03.15-.05.25,0,.11-.02.19-.05.25,0,0,0,.01,0,.03,0,0,.01,0,.03,0ZM131.72,26.7l.04-.06v-.03s.04,0,.04,0v.03s.02.04.02.04c0-.02,0-.03,0-.03,0-.04,0-.08-.01-.1-.02-.03-.04-.04-.09-.05l-.02.09v.06s-.02.03-.02.03h.03ZM131.27,26.51s.02-.03.04-.02c.04,0,.05,0,.04-.02,0-.04.01-.07.02-.09.05-.03.07-.08.07-.15.01-.06.02-.1.03-.13h.03s-.02-.05-.01-.09c.03-.15.07-.25.1-.31l-.02-.07s-.06,0-.07.02c-.03.02-.04.05-.05.09l-.08.34v.06s-.03.04-.06.06c0,.02-.01.05-.02.09.01.05,0,.1-.03.16l.02.07ZM131.28,25.56s.03,0,.04-.02v-.03s.02-.06.02-.06h-.06s.02.06.02.06v.03s-.01.03-.01.03ZM131.82,26.4l-.02-.04.11-.04v-.03s-.02-.04-.02-.04c-.08.05-.1.09-.09.11l-.04.02s-.02.06-.04.06l.06.04.05-.09ZM131.87,26.18l-.03-.04s.04-.05.05-.09l.08-.05-.06-.04s-.04.05-.05.09v.03s-.04.02-.04.02l.02.07h.03ZM131.99,25.91s0-.03-.02-.04c0-.02,0-.03-.02-.04,0-.02.02-.04.04-.06l.04-.06-.14.04.02.07s.03.02.02.04l.06.04ZM131.4,25.32l.02-.09s-.02-.06-.01-.1c0-.02,0-.04.01-.06.03-.02.03-.05.02-.09l.04-.02.03-.16s0,0-.03,0c0-.02.02-.04.05-.06.03-.04.04-.07.02-.09,0-.02,0-.04.01-.06-.02-.03-.03-.04-.03-.04.03-.02.04-.03.04-.06.05-.03.07-.05.05-.06-.05-.06-.05-.09.02-.09l.04-.02s0-.11,0-.19c0-.02,0-.04-.02-.07,0-.02.02-.04.04-.06l.02-.09-.11.04v.06c-.04.1-.07.23-.13.37-.03.13-.05.28-.07.48l-.02.09-.07.15-.03.16s0,.06.04.11l.04-.02ZM132.08,25.21l-.02-.07-.07.02s.02.06.01.1c0,.02,0,.04.02.07h.03s.03-.12.03-.12ZM131.86,25.29l.09-.41.07-.31-.02-.07c.08-.05.1-.1.06-.15,0-.02,0-.03-.02-.04l-.04.02s.01.1,0,.16c-.03.02-.05.06-.06.12v.26c-.02.13-.06.2-.11.24l-.03.13.02.07.04-.02ZM132.18,25.17v-.1s-.04-.04-.04-.04c.05-.03.07-.06.05-.09,0-.04.01-.07.02-.09l.05-.22s0-.04.01-.06c.02-.02.02-.04-.02-.07-.02,0-.03,0-.03,0,0-.02.02-.04.04-.06h-.03s-.07.01-.07.01c0,.02-.02.05-.05.09,0,.02.01.05.05.08,0,.02,0,.03,0,.03.02,0,.03,0,.03,0l-.04.02s-.07.04-.08.08c.02.03.02.04.02.04.03.07.03.14,0,.19v.06s.06.11.06.11h.03ZM131.68,23.85c.08-.05.11-.07.11-.07v-.06s.04-.13.04-.13t0,0s0-.03,0-.03h-.03c-.08.04-.12.12-.15.22.02,0,.03.03.02.07ZM131.79,23.51s-.02-.06-.01-.1c-.02,0-.03,0-.04.02l-.02.09.07-.02ZM132.14,23.98l-.06-.04v.03c-.02.08-.03.14,0,.16,0,.02,0,.03.02.04l.04-.19ZM131.91,23.41v-.03s-.01-.01-.05-.04c-.02,0-.03,0-.04.02,0,.04,0,.08.01.1,0,0,0,.01,0,.03.02,0,.04,0,.07-.02v-.06ZM135.48,29.74s.03,0,.03,0c.03-.02.05-.02.07-.02v-.03s-.09.01-.09.01v.03ZM132.33,24.35l.03-.16.12-.56.04-.19s0-.03-.02-.04c0,0-.01,0-.03,0,0,0,0,.01,0,.03.01.05,0,.09-.06.12-.02,0-.03,0-.04.02,0,.04-.02.09-.03.16,0,.04.02.08.07.11v.06s-.03,0-.05.02c0,0,0-.01,0-.03h-.03s0,.02,0,.02c-.03.06-.06.11-.07.15.01.05.01.08.01.1h-.03s.02.06.02.06c.02,0,.02.01,0,.03l-.02.09h.1ZM131.9,23.27s.03,0,.04-.02c.03-.06.06-.15.09-.27h-.03s-.05.05-.09.1c-.03.06-.06.11-.07.15l.06.04ZM135.85,29.43l-.06-.04-.04.02s-.04.08-.09.11l-.05.06v.03s.23-.18.23-.18ZM132.59,22.67c-.03-.05-.05-.08-.05-.08l-.02-.07h.03s0,.06.04.11v.03ZM137.06,27.92s.07,0,.08-.05l.04-.06s0-.03-.02-.04h-.03s-.04.05-.04.05l-.02.09ZM137.6,27.35s0-.03-.02-.04l-.12.1.02.04.12-.1ZM137.74,27.19v-.06s-.09.04-.09.04l.02.04.07-.02ZM138.21,26.67s.04-.07.1-.14c0,0-.01,0-.03,0,0,0,0-.01,0-.03,0,.02-.03.05-.08.08v.06s-.05.02-.05.02h.06ZM138.51,26.93s.01-.06.09-.11v-.03s-.02,0-.02,0l-.12.1s0,.02-.01.06l.07-.02ZM138.49,26.27s-.03,0-.03,0c0-.02,0-.03,0-.03-.05.03-.08.06-.08.08l.02.07.09-.11ZM138.99,25.62h.1s.04-.04.04-.04c0-.02,0-.03-.02-.04v-.03s.03-.09.03-.09h.03s-.03,0-.03,0l-.13.14-.04.02.02.04ZM140.28,39.88c-.06-.01-.12-.04-.18-.07-.04-.03-.09-.05-.15-.07-.04-.03-.09-.04-.16-.03-.06-.01-.13-.04-.21-.08l-.35-.21h-.06c0-.1-.04-.18-.12-.24s-.13-.11-.16-.17c-.07-.06-.14-.12-.19-.17-.03-.07-.07-.12-.13-.16-.01-.05-.03-.09-.07-.15-.03-.05-.06-.11-.09-.18l.06.04-.25-.68c-.06-.21-.07-.55-.01-1.02l-.08-.21s-.02-.05-.02-.07c.03-.04.05-.07.05-.09.03-.34.06-.57.08-.67.06-.27.12-.49.17-.65,0,.22-.02.38-.04.48h.03c.03-.14.05-.34.07-.6h-.03s-.03.06-.05.08c-.02-.11,0-.28.05-.51.05-.25.11-.45.16-.59.05-.12.17-.42.36-.9.03-.06.07-.15.12-.27.07-.14.12-.25.14-.33.01-.06.02-.13,0-.19.02-.08.05-.16.09-.24.25-.47.5-.84.73-1.12.14-.17.28-.39.41-.67.06-.07.12-.15.18-.22.09-.09.17-.19.26-.3.06-.07.11-.16.15-.26.07-.12.15-.22.23-.31.13-.19.22-.31.28-.37.03-.04.05-.1.07-.18v-.03s.47-.49.47-.49l.42-.3c.22-.21.36-.35.41-.4.13-.1.27-.19.42-.27.17-.07.32-.16.45-.26l.6-.33c.23-.15.42-.23.57-.24.55-.14.97-.23,1.24-.26l.25-.11c.12-.04.27-.04.46,0l.66.11c.12.03.25-.03.37-.18l.14-.2.04-.02h.03c.06.02.11.06.14.13.05.06.08.12.09.18l.06.18c0,.09.03.17.08.25.05.08.09.14.12.19.02,0,.03.02.02.04-.05.03-.06.1-.04.19,0,.04,0,.11.02.2l.04-.02s.06-.11.08-.21l.07-.02.46.3c.08.04.15.05.22.05.02-.02.06-.02.1-.01.06.01.1.03.12.06.04.03.07.06.11.09l.02.04c.12.03.13.06.01.1l.33.14c.15.12.25.22.3.29.1.15.15.25.16.3,0,.07.04.14.09.21.05.08.09.14.12.19l-.03.13c.09.11.16.18.22.21.06.03.12.03.2-.02-.02.1-.02.18.01.23.05.06.09.1.1.12.08.06.11.12.09.18,0,.04-.02.07-.02.09v.1c.1.3.11.61.04.92l-.11.66c-.07.33-.24.8-.5,1.4l-.36.74c-.15.27-.25.48-.3.62l-.14.33-.04.06.03-.13-.17.19c-.06.1-.16.23-.28.4-.1.15-.24.33-.41.53-.45.45-.74.74-.87.86-.18.2-.35.37-.54.51l-.02.09s.06,0,.07-.02c.02,0,.08,0,.17-.03-.09.11-.18.17-.27.17-.24.01-.44.13-.6.36-.05.12-.16.26-.35.42-.81.52-1.22.78-1.22.78,0,0-.33.21-.99.64-.02.02-.04.05-.05.09,0,.02-.02.04-.04.06l-.13.14-.23.31c-.13.1-.24.09-.32-.04l-.1-.12-.07.02c-.37.29-.59.47-.67.54l-.13.17-.05-.08s-.03.02-.08.05l-.12.1-.12-.06s-.13.03-.25.11c0,.02-.03.03-.07.02-.02,0-.03,0-.03,0-.03-.07-.08-.1-.14-.1-.07,0-.12,0-.16,0-.18,0-.33-.03-.47-.1-.02,0-.07-.02-.16-.03-.06-.01-.12,0-.17.03-.05.01-.11,0-.2,0l-.56-.15ZM138.53,36.33s0-.08-.03-.17h-.03c.05.07.07.13.06.17ZM139.9,38s.04-.01.03,0c.02,0,.04,0,.06.01h.43c-.03-.06-.06-.08-.08-.09-.04,0-.1-.02-.19-.04-.08-.04-.15-.05-.22-.05-.05.01-.12,0-.23-.02-.08-.04-.15-.05-.22-.05-.04,0-.09-.03-.15-.06-.04-.03-.07-.02-.11.04h-.03c-.08-.05-.19-.12-.34-.24l-.22-.21c.02.09.07.17.15.23,0,.02,0,.05.01.1.02.03.05.02.1-.01.01.05.04.07.08.08.06.01.09.03.09.05.02.03.04.04.09.05l.31.1-.05-.08.29.16h.19ZM139.94,38.3c-.03-.05-.07-.08-.11-.09v.03s.11.06.11.06ZM139.1,36.71l-.14-.13c.03.07.05.12.07.15h.06s0-.02,0-.02ZM138.76,36.64v-.06s.04.02.04.04c.02,0,.04.02.06.04,0-.09-.04-.18-.1-.28-.04-.1-.05-.17-.02-.23l-.04-.11s0-.03-.02-.04c.01-.06.01-.11,0-.13l.11.09c-.04-.12-.06-.18-.06-.18-.02-.11-.04-.24-.05-.37h-.03s-.02-.06-.02-.08c0-.04,0-.08-.01-.1l-.02.09v.03s.05.04.05.04c-.02.02-.04.06-.06.12-.01.06-.02.18-.01.36-.02.1-.03.17,0,.19.03.18.08.37.17.56h.03ZM139.81,37.65c.1.02.19.05.24.09v-.03s-.48-.33-.48-.33l.24.41v-.13ZM139.38,37.23l.06.04c.14.07.22.1.24.09.07,0,.12,0,.16.03.06.03.11.05.16.03.05-.01.11,0,.2,0,.08.02.15.02.19,0l.06.04.17-.03.14-.04v-.03s.06,0,.11-.04l-1.55-.24-.02-.07s0,.03,0,.03l-.6-.42s.06.09.17.27c.03.05.07.09.1.12.06.03.11.07.14.1h-.13s.08.09.08.09l.12.03.21.11v-.13ZM140.28,37.62s.06.03.06.01c0-.04.02-.07.02-.09l-.2.02.12.06ZM139.68,38.41c.06.01.14.04.24.09.12.03.22.04.29.03.76.01,1.38-.13,1.86-.42l.09-.11-.11.04h-.03c-.07.02-.14.05-.21.08-.05.03-.1.07-.15.1-.05-.08-.07-.06-.08.05-.02,0-.04,0-.06-.01-.02-.03-.04-.03-.06-.01l-.4.04-.04.06c-.06-.01-.12-.01-.16,0-.04,0-.11,0-.2.02l-.31.06c-.09,0-.16,0-.23-.02-.04-.03-.08-.05-.12-.06h-.03c-.06-.02-.11-.02-.13,0h-.06s-.07,0-.07,0v-.1s-.07,0-.12.04c-.02.02-.05,0-.09-.05,0-.02,0-.02-.03,0,0,.04,0,.06.02.07.07.06.14.1.21.11ZM141.19,38.08v-.03c-.06,0-.13.01-.19.02-.05.01-.09.02-.14.04v.03s.33-.06.33-.06ZM140.45,37.59c.22,0,.39.02.51.05-.12-.07-.21-.11-.27-.12h-.03c-.04.07-.11.08-.2.02l-.07.02.06.04ZM141.11,37.54s.02,0,0,0c0-.02,0-.03,0-.03-.04,0-.08,0-.1.01l-.07.02s.06.01.06.01h.1ZM140.97,37.31c.27-.03.57-.04.89-.04v-.03s-.88,0-.88,0v.06ZM141.73,37.57l-.02-.04s-.06,0-.11.04h.03s.1,0,.1,0ZM142.4,37.95s-.03-.04-.03-.04c.03-.02.03-.04.01-.06l-.06-.04c-.1.07-.15.1-.15.1l.16.03h.06ZM143.43,39.25h-.03s-.06,0-.11.04c.02,0,.03.02.03.04l.11-.07ZM141.97,37.23s.08,0,.17-.03v-.03s-.17.06-.17.06ZM142.45,37.89s.03-.05.08-.08l-.06-.04-.04.06.02.07ZM141.94,37.06s.08,0,.17-.03l-.02-.04-.15.07ZM143.78,39.92c.05-.03.09-.05.11-.04,0,0,.02.03.05.08l-.16-.03ZM142.57,37.76s.03.06.06.04c.05-.01.08-.02.1-.01l-.08-.08-.09-.02.02.07ZM142.4,37.03c.09-.02.24-.07.45-.13v-.03s-.48.16-.48.16h.03ZM143.08,37.08s-.03,0-.03,0c0-.02,0-.03,0-.03l.54-.21v.03s-.51.22-.51.22ZM140.69,37.97c.07,0,.15-.01.26,0,.11-.02.23-.04.34-.06.34-.08.63-.17.85-.28l.33-.16.25-.08.45-.26c.21-.08.36-.15.44-.2l.7-.37.41-.24s.19-.12.57-.37c.05-.01.07-.03.08-.05,0-.02.02-.04.04-.06.15-.1.23-.15.23-.15.08-.05.14-.09.19-.12.06-.05.11-.1.16-.13-.12-.03-.22,0-.28.1,0,0,0,.01,0,.03,0,0-.01,0-.03,0,0,.04-.09.13-.26.27l-.18.06-.18.06v-.03s-.09.14-.09.14l-.02-.07-.11.07s.01.04.06.04c-.05.03-.08.04-.1.01-.04,0-.1.01-.18.06-.05.03-.08.06-.08.08l-.05.09h-.06s.03,0,.03,0c0-.02,0-.03,0-.03-.02-.03-.07-.02-.17.03-.08.05-.14.09-.19.12-.06.05-.11.09-.15.1-.05.01-.08.03-.11.04l-.19.12h-.06c-.27.12-.48.21-.64.24-.07,0-.15.04-.25.11v.03s.3-.06.3-.06c0,.02,0,.03,0,.03.02,0,.03,0,.03,0l-1.17.57c-.16.05-.35.1-.55.14-.21.04-.43.09-.66.15.02.03.04.03.06.01ZM142.93,36.88c.14-.04.27-.09.4-.18h-.06s.14-.08.14-.08c.03-.02.05-.02.07-.02.05-.01.07-.03.08-.05l.18-.06s0-.03-.02-.04l-.15.1c-.13.01-.23.04-.28.07v.06c-.11.02-.18.03-.25.02l.02.07.21-.05c-.14.06-.25.11-.33.16ZM143.78,36.74s-.06.02-.1.01h-.03s0-.04,0-.04v.1s.12-.07.12-.07ZM144.16,37.38s.09-.07.18-.09h-.03s-.05.02-.07.01c-.02,0-.05.01-.08.05v.03ZM143.78,36.71s.05-.02.07-.02c.05-.01.08-.04.11-.07.02,0,.03.02.02.04l-.18.06h-.03ZM144.08,36.25c.18-.05.32-.1.39-.14-.02,0-.03,0-.03,0,0-.02,0-.03,0-.03l-.37.21-.26.14s0,.03.03.04l.24-.21ZM145.22,37.18h-.03c-.18.11-.27.16-.27.16h.03s.27-.16.27-.16ZM142.43,37.99c.06.01.11.01.13,0,.21-.08.42-.19.63-.32.12-.04.26-.1.43-.17.17-.09.33-.17.47-.22l.07-.02.09-.11.4-.21.31-.23.73-.5.39-.28.09-.11.16-.13.22-.25c.16-.14.27-.25.33-.32v-.06s-.05-.01-.05-.01l-.09.11-.73.63c-.08.07-.17.14-.27.2-.08.07-.16.14-.24.21-.05.03-.12.08-.2.15-.05.05-.13.1-.23.15-.03.04-.09.07-.18.09l.02.04s-.03.07-.05.09c-.15.1-.29.17-.4.21l-.21.08s-.01,0-.03,0c0,0,0,.01,0,.03l.06.04-.08.05c-.05.03-.12.06-.21.08-.07.03-.16.06-.25.11l-.53.31s-.26.12-.69.31l-.08.05ZM143.58,37.19l.45-.26s.26-.14.86-.47l.58-.4s.08-.05.09-.11l.3-.16.16-.13.09-.11s.05-.03.08-.05c.03-.02.05-.03.08-.05l.13-.14s.1-.08.4-.34v-.06s-.06.02-.06.02l-.35.25c-.22.21-.37.35-.44.39-.06.05-.15.13-.28.23-.11.11-.21.18-.31.23,0,0-.39.25-1.18.76l-.64.39h.06ZM146.04,36.87v-.03s-.53.34-.53.34l.06.04.47-.36ZM146.56,36.26l-.07.02s0,.08.01.1l.06-.12ZM146.07,35.37l-.05-.08-.11.07s0,.03.02.04l.14-.04ZM146.32,36.04l.2-.15h.03s-.2.16-.2.16h-.03ZM145.7,35.42c.13-.08.3-.21.51-.38,0,0,0-.01,0-.03,0,.02-.02.03-.04.02-.12.06-.29.18-.5.35v.03s.02,0,.02,0ZM140.43,36.15c.09,0,.26-.02.5-.06.05-.01.09-.02.14-.04.07,0,.12,0,.16,0,.21.04.43.05.65,0,.23-.06.38-.09.45-.1.22-.02.41-.06.55-.14l.73-.37.59-.3s-.01.05-.02.09c.01.05,0,.09-.06.12-.03.04-.07.07-.12.1-.03.02-.05.04-.08.08l-.32.26c.06.01.12,0,.17-.03l.2-.15s.07-.06.11-.07c.07,0,.11,0,.13,0,.14-.04.25-.08.32-.13.1-.07.2-.12.3-.16l.24-.21c.08-.05.17-.13.28-.23.06-.05.13-.1.23-.15.1-.07.16-.15.19-.25h.03s.16-.12.16-.12l.52-.44c.17-.18.33-.32.48-.42.03-.04.06-.08.1-.14.03-.06.08-.09.15-.1v-.06s.07-.09.07-.09l.04-.02-.02-.04s.01-.06.01-.06l.27-.2-.2.02c.05-.03.11-.06.18-.09.07-.03.12-.07.16-.13,0-.02,0-.03,0-.03.02,0,.03,0,.03,0l.04-.02-.06-.04s0,0-.03,0c0,0,0-.01,0-.03v-.03s.04-.02.04-.02c.08.04.13.02.15-.07,0,0,.03-.06.1-.17,0-.02,0-.03,0-.03l.05-.09c.07-.12.14-.25.22-.41.15-.29.25-.5.3-.62.1-.24.15-.42.15-.53.01-.04.03-.09.07-.15.03-.06.03-.13-.02-.2v-.03c.06-.03.07-.06.06-.09-.02-.03-.05-.04-.09-.05l-.34-.07.11-.07-.09-.02h-.03s-.58-.07-.58-.07c-.02,0-.07,0-.16,0-.07,0-.11-.04-.14-.13h-.03s-.05-.04-.09-.03c-.04,0-.08-.03-.12-.06-.15-.03-.28-.03-.4.01l-.28.07.12.06c-.23.06-.37.11-.42.14l-.07.02c-.14.12-.24.2-.31.23l-.22.12-.34.06.02.07h.29c-.05.03-.09.04-.11.04-.07,0-.17.02-.3.03-.11,0-.2.01-.27.04-.03.02-.12.04-.28.07-.14.01-.25.09-.34.22h-.1s-.06-.02-.05-.07c.02-.08.02-.15,0-.19,0,0-.01,0-.03,0,0,0,0-.01,0-.03-.08-.02-.17,0-.27.04-.08.05-.13.08-.15.1-.05.03-.09.05-.11.04-.02,0-.04,0-.07.02-.02.02-.04.03-.04.06-.06.07-.12.15-.18.22-.05.05-.11.12-.17.19-.66.82-1.05,1.31-1.17,1.48-.12.15-.38.53-.77,1.14-.04.08-.09.17-.15.26-.06.1-.11.16-.14.2l-.24.5-.51,1.3c-.01.06,0,.13.02.2.05.06.11.08.18.07ZM146.4,36.72c.14-.12.27-.24.4-.34.16-.12.3-.24.44-.36h-.03c-.11.08-.24.18-.39.3-.13.1-.28.22-.44.36l.03.04ZM146.64,36.38c.1-.07.17-.1.22-.12-.02,0-.03-.02-.03-.04-.07,0-.13.06-.2.15ZM146.31,35.16s-.04-.04-.06-.04c0-.02,0-.03,0-.03,0,0-.03.02-.08.05,0,.04,0,.07.05.08l.08-.05ZM144.2,37.52l.07-.02.71-.4.05-.09.11-.04s.03-.03,0-.03l.07-.02.06-.12-.03.13c.05-.05.12-.1.2-.15.08-.05.12-.1.13-.17.04,0,.09,0,.14-.04.09-.02.22-.11.38-.25.08-.07.17-.15.28-.23.11-.09.21-.18.32-.29.08-.05.09-.09.03-.13l.04-.02.54-.51c.23-.26.37-.4.42-.43h.03c-.04.06-.09.12-.17.17.07.06.14.05.2-.02.09-.09.16-.18.22-.28.07-.12.15-.22.23-.31.1-.15.16-.25.19-.29,0-.02.03-.05.08-.08l.1-.17c.13-.19.19-.33.19-.42,0-.02.02-.03.04-.02.11-.13.16-.23.13-.3.06-.07.09-.13.1-.17l-.08-.08-.08.08c-.06.18-.16.4-.3.65h-.03s.06-.13.06-.13c-.05.03-.09.05-.11.04l.15-.23s.06-.11.08-.21c-.11.02-.17.04-.18.06l-.31.36c-.08.18-.18.36-.28.53l-.02.09.16-.13-.02.09.08-.05s-.03.07-.05.09l-.14.2c-.05.05-.11.11-.16.16-.04.06-.08.11-.13.17-.06.07-.14.14-.24.21-.77.93-1.64,1.7-2.63,2.31.02.03.04.04.09.05l-.07.02h-.03s-.1,0-.18.05c-.07.03-.11.06-.12.1v.03s-.02.06-.02.06h-.06s.01-.08.01-.08l-.19.12.06.04-.07.02-.04.06-.05-.08-.16.13h.03s.03.01.03.01c.02-.02.05-.02.07-.02l-.04.06h.03s.09-.1.09-.1ZM145.34,37.08l.3-.16s.07-.05.12-.1c.08-.07.15-.1.22-.08.02,0,.03,0,.04-.02.02-.02.05-.02.07-.02v-.03s-.09.01-.09.01c0,0-.01,0-.03,0,0,0,0-.01,0-.03.07-.03.2-.1.37-.21v.03s-.24.18-.24.18l.06.04.35-.28s0-.04.01-.06c.03-.04.07-.07.12-.1,0,0,.1-.07.3-.2.17-.16.25-.24.25-.24l.41-.37.13-.14h-.13s.34-.35.34-.35l.05.08c.2-.22.37-.42.52-.61.15-.19.28-.35.4-.5,0-.02,0-.03-.02-.04,0,.04-.03.06-.08.05l.06-.12.12.06-.04-.14v.03s.03-.19.03-.19c-.03.02-.05.03-.08.05,0,0,0,.01,0,.03l-.4.5-.75.89-.1.14-.27.2-.66.61c-.08.07-.16.13-.24.18s-.14.1-.2.15l-.67.54-.31.23h.03ZM146.79,35.69s.07,0,.07-.02l.66-.61v.06s.11-.1.11-.1l.05-.06-.09-.02-.07.02-.04.06c-.09.11-.3.33-.63.65,0,0,0,.01,0,.03,0,0,0,0-.03,0ZM144.29,31.64c.11-.32.21-.57.29-.72.04-.06.08-.09.15-.1l.23-.15c-.15.1-.27.23-.35.38-.06.16-.1.28-.14.36-.07.12-.11.21-.12.27l-.07.02v-.06ZM144.03,30.28s.03,0,.04-.02l-.09-.05s-.01,0-.03,0c0,0,0,.01,0,.03.02.03.05.04.09.05ZM144.25,30s-.01,0-.03,0c0,0,0-.01,0-.03l-.21.22.06.04.18-.22ZM147.12,34.45l-.02-.04c-.06.07-.09.12-.1.14l.12-.1ZM147.03,34.1h-.03s-.19.12-.19.12c0,.02,0,.03,0,.03.02,0,.03,0,.03,0l.2-.15ZM146.61,34.67l.05.08v-.06c.06-.03.09-.05.09-.05l.17-.16.27-.33c.2-.22.32-.35.35-.38l-1.06.98s0,.03,0,.03c.02,0,.03,0,.03,0l.12-.1ZM147.33,34.66s0-.03-.02-.04l-.12.1h.03s.11-.07.11-.07ZM144.4,29.9s0-.02.01-.06l-.07.02s-.03.05-.08.08c.02,0,.03.02.03.04l.11-.07ZM144.09,29.24h.03s-.06-.04-.06-.04l-.28.07.02.04.28-.07ZM147.76,35.28c.05-.05.09-.1.1-.14,0-.04.03-.07.05-.09v-.03s-.02,0-.02,0c-.01.06-.04.11-.07.15-.02.02-.05.04-.08.08.02,0,.03.02.02.04ZM148.08,35.61s.05-.03.08-.05c.02-.02.04-.03.04-.06l.09-.11s-.01,0-.03,0c0,0,0-.01,0-.03l-.21.22s.03.02.02.04ZM147.25,35.98c.17-.09.27-.15.3-.16l.12-.1h.03c.07-.09.19-.22.38-.4.03-.02.04-.05.05-.09l.14-.2s0-.02,0,0c.02,0,.03,0,.04-.02h.1s.01-.06.02-.1c.03-.06.08-.11.13-.17l.19-.25.06.04s.06,0,.11-.04c-.05-.06-.08-.08-.08-.08,0,0,0-.01,0-.03.03-.02.04-.03.05-.06h-.06s-.07.17-.07.17h-.1s-.04.06-.05.1c0,.02-.02.04-.04.06-.07.12-.13.2-.19.25-.32.26-.57.5-.74.72l-.37.35v.03ZM144.71,29.84s0-.03,0-.03c.02,0,.03,0,.03,0l.17-.16v-.03c-.1.07-.16.12-.19.15,0,0,0,.02-.01.06ZM147.31,34.49s-.03,0-.03,0c0-.02,0-.03,0-.03h.03s.22-.27.22-.27l.29-.3v-.06s.06-.06.07-.12l.13-.17c-.05.03-.13.1-.24.21,0,.02-.03.03-.07.02l-.06-.04c.06.01.1,0,.1-.01.03-.02.04-.05.05-.09l-.11.04-.04.06-.36.48.02.07h.03s-.03.08-.05.09l-.12.1.03.04h.1ZM148.27,35.35c.16-.05.25-.14.25-.27-.05.05-.1.1-.13.14-.03.04-.07.08-.13.14ZM144.53,29.14c-.03-.05-.05-.08-.05-.08l-.08.05s0,.01,0,.03c0,0,0,0,.03,0h.1ZM148.5,34.55l-.13.14s.03.02.02.04l.1-.17ZM144.89,28.86c-.06-.01-.12-.01-.16,0l.02.04.14-.04ZM145.12,28.85v-.03s-.17.06-.17.06l.17-.03ZM148.77,34.25l-.02-.04-.13.14h.06s.09-.1.09-.1ZM144.8,29.14c.03.05.06.07.09.05.03-.02.05-.03.08-.05.04,0,.07,0,.1-.01.03-.02.04-.02.04-.02.03.05.06.07.09.05.03-.04.06-.06.08-.08l.12-.1.06.04s0-.03,0-.03c.02,0,.03,0,.03,0,.13-.01.2-.02.2-.02.07,0,.11-.02.14-.04.05-.03.09-.06.11-.07l.11-.07v-.03s-.02,0-.02,0c-.07,0-.14.03-.21.05-.05.03-.11.05-.18.06-.06-.01-.12,0-.17.03-.02,0-.04,0-.06-.01,0-.02,0-.02-.03,0l-.14.04-.07.02-.23.02s-.06,0-.1.01c-.05.01-.05.04-.02.09l-.23.02v.03s.08.02.12.03c.05-.01.08,0,.09.02ZM148.98,34.33l.04-.06-.12-.06s0,.01,0,.03c0,0,0,0-.03,0l.02.04c.03.05.06.08.08.08v-.03ZM147.89,33.31c.07-.03.16-.1.27-.2.09-.11.14-.19.15-.23.04-.06.03-.14-.01-.23l-.29.43-.19.25.07-.02ZM147.96,32.96c.05-.03.08-.05.08-.05v-.13s.05.03.06.01c.02-.02.05-.03.08-.05-.02,0-.03,0-.03,0,0-.02,0-.03,0-.03-.05.03-.09.05-.11.04v.03s-.05.06-.07.12v.06ZM148.47,33.5l.08-.05.04.14-.04.02-.07-.11ZM148.5,32.91c.05-.03.11-.11.18-.22-.07,0-.14.06-.23.15l.02.07h.03ZM149.04,34.18c.07-.03.07-.07,0-.13h.06s.06.04.06.06l.06-.12-.02-.07s.03-.03.07-.02c.02,0,.03,0,.04-.02.03-.02.04-.06.06-.12,0-.04,0-.08-.01-.1.12.03.16-.05.12-.24l-.12.24-.19.25h.03c-.06.08-.11.12-.16.14.02.03.02.07,0,.13ZM149.33,33.29h-.03s-.31.38-.31.38l.06.04.29-.43ZM148.14,31.53c-.02-.09-.01-.14.03-.16.05-.03.09-.06.12-.07l-.15.23ZM149.34,33.26c.07-.12.14-.22.2-.32-.09.02-.14.05-.15.07l-.03.13s-.03.07-.05.09c.02,0,.03.02.02.04ZM149.64,33.39l.1-.17.13-.3h-.03s-.34.51-.34.51l.02.04.11-.07ZM149.42,32.59s-.03-.02-.02-.04l-.12.1s.03.02.02.04l.12-.1ZM149.19,32.61s0,.01,0,.03c0,0,.01,0,.03,0l.04-.06-.11-.09.07-.02h.03s.06.02.06.02c-.04,0-.06-.03-.05-.08,0-.04.04-.1.1-.17l-.04-.14s-.04,0-.07.02c-.03.02-.04.03-.04.06l-.12.27v.19s.1-.04.1-.04ZM147.02,28.83c.06.01.13,0,.2-.02.07-.03.12-.07.16-.13-.07,0-.15.02-.24.05-.07.03-.14.05-.21.05l.09.05ZM146.44,27.43v-.03s-.02-.04-.02-.04l-.18.09v.03s.2-.05.2-.05ZM149.46,32.08s.02-.03.04-.02l-.11-.09-.02-.04.09-.11s0-.02.01-.06l-.08.05-.07.15s-.03.07-.05.09h.16s.02.04.02.04ZM146.71,27.39l-.11-.09s-.06,0-.11.04c.03.05.05.08.05.08l.17-.03ZM149.56,32.69l.03.04v.06s.02,0,.02,0c.01-.06.05-.13.11-.21h-.03s-.01,0-.04.02c0,.02,0,.04-.01.06,0-.02,0-.03-.03-.04.06-.16.13-.35.22-.57.11-.22.18-.41.19-.58l-.59,1.38.02.04.11-.21ZM149.47,31.75s0-.04.01-.06c.03-.02.04-.02.04-.02-.02-.03-.04-.04-.09-.05l.04.14ZM150,32.65l.02-.09c.02-.1.05-.19.08-.24h-.03s-.11.33-.11.33l.02.04v-.03ZM149.89,32.53c.08-.16.13-.28.14-.36h-.03s-.18.35-.18.35l.02.04.04-.02ZM147.73,28.43l-.09-.02-.04.02c.06.01.09.03.09.05l.04-.06ZM148.98,30.53l.05-.22h-.03s-.03-.01-.03-.01v.06c-.03.06-.03.11,0,.13v.06s.02-.02.02-.02ZM150.22,32.04l.02-.09h-.03s-.05.08-.05.08l.02.07.04-.06ZM146.75,27.36c.09-.02.16-.05.21-.08.05-.01.09-.02.14-.04.05-.01.1-.01.16,0,.02,0,.05.01.09.02.05-.01.07-.04.08-.08l.12-.1s.03,0,.04-.02c.02,0,.03,0,.03,0,0-.02,0-.03,0-.03h-.03s-.1.01-.17.02c-.04,0-.08.02-.11.07-.03.06-.13.09-.28.1l-.37.05c.03.05.06.08.08.08ZM149.68,31.07c.01-.06.03-.09.05-.09v-.06s0-.03-.01-.04l-.08.08s0,.06.04.11ZM150.25,31.92s.03,0,.04-.02l.08-.24s-.08.03-.12.1c-.03.06-.04.11-.03.16h.03ZM148.11,28.48s.05-.1.07-.18h-.03s-.1.17-.1.17h.06ZM147.91,28.2s.02,0,.06.01h.1s.06-.03.1-.02v-.06s-.25,0-.25,0v.03s-.04.02-.04.02c.02,0,.03,0,.03,0ZM149.8,31.89c.1-.24.18-.44.26-.6l-.03.16h.03s.14-.36.14-.36c-.04,0-.07,0-.1.01v-.03c.1,0,.13-.06.11-.17,0-.02,0-.04-.02-.07-.02-.03-.03-.05-.05-.08.02-.08.02-.15.01-.19l-.39,1.32h.03ZM147.81,28.08s.11-.04.25-.08c.03-.02.07,0,.13.03.08.02.15.01.2-.02.12.03.17,0,.12-.1-.02,0-.05-.01-.09-.02-.02-.03-.04-.03-.06-.01-.33.02-.54.03-.63.03h-.03s0,.02,0,.02c.02.03.04.04.06.04.04,0,.06.02.06.04v-.03s-.04.05-.04.09h.06ZM149.7,30.85c.05-.03.08-.05.08-.05.03-.04.04-.08.03-.13,0-.04.03-.08.06-.12,0-.04,0-.1,0-.16,0-.09.02-.15.07-.18l-.07-.15h-.03c-.12.03-.14.1-.08.21l.02.2-.04.06-.05.25.02.07ZM147.98,27.14v-.06s-.32.03-.32.03l.02.07.3-.03ZM148.91,28.72c.15.01.31,0,.47-.06l-.12-.06.04-.06-.12-.06s0-.01-.02-.04c0-.02,0-.03-.02-.04s-.07-.02-.16-.03c-.08-.02-.15-.01-.2.02.02-.08-.01-.13-.1-.15-.06-.01-.11-.04-.15-.07h.13c-.05-.06-.12-.09-.21-.08-.08-.02-.15-.01-.2.02,0,.04,0,.06.02.07l.12.03s.06.04.12.06l-.07.15-.05-.21-.13.17s-.03.05-.08.08v.03s.06-.02.06-.02c.05.08.1.11.14.1.19.04.32.06.41.06l.12.06v.03ZM148.9,28.19l-.09-.02.07.11.02-.09ZM150.47,30.92s.03,0,.04-.02v-.19s-.02,0-.02,0l-.02.23ZM148.07,27.16c.06.01.12,0,.17-.03v-.03s-.17.06-.17.06ZM148.21,26.96l-.06-.04-.1.14.02.04.13-.14ZM150.23,30.05v-.23s-.03.03-.05.02v.19s.05.01.05.01ZM148.61,47.21l-.04-.14c-.02-.09-.03-.17-.02-.23.04-.38.08-.66.11-.83h.03s.08-.53.08-.53l.14-.33c.04-.17.07-.28.11-.34.08-.16.12-.27.14-.33v-.06s-.02,0-.02,0c0,.02,0,.03,0,.03-.02.02-.04.05-.05.09-.03.04-.1.14-.2.32v.03s-.04.1-.14.17l-.12.27v.03s-.03-.04-.03-.04l.06-.12s0-.06-.02-.07l-.02-.07-.04.06-.06.12s0,.07.05.08v.03s-.12.69-.12.69l-.04.02v-.03s.03-.55.03-.55l.04-.32c.05-.23.13-.42.25-.57l.05-.06s.02-.03.04-.02v.06s-.05.09-.12.21l.02.07.02.04.05.08s.01-.06.01-.06v-.03c.02-.06.04-.12.08-.18.06-.05.08-.1.07-.15.05-.01.08-.05.09-.11.03-.06.06-.11.07-.15.06-.05.11-.14.15-.26.06-.1.11-.17.15-.23.12-.24.22-.4.3-.49l.18-.22c.13-.19.2-.33.22-.41l.02-.09c.02-.08.05-.18.09-.27.07-.1.1-.16.11-.21s.02-.06.04-.06c.03-.04.07-.08.13-.14.05-.05.11-.12.17-.19.06-.05.09-.11.1-.17.03-.06.07-.12.1-.17v-.03s-.05.04-.06.02c0-.02,0-.03-.02-.04-.05.03-.08.06-.08.08-.03.04-.06.07-.09.11,0,.04-.03.08-.06.12-.08.05-.12.13-.12.24,0,.04-.04.06-.08.05l-.02-.04v-.06c.05-.06.08-.13.12-.21.04-.1.09-.18.15-.23.18-.22.32-.41.42-.56.07-.12.13-.22.2-.32.08-.09.16-.18.22-.28l.04-.06v-.03s-.02,0-.02,0c-.07.03-.14.1-.21.22-.03.04-.07.07-.12.1-.03.02-.05.03-.08.05-.07.12-.11.21-.12.27l-.08.08s0,.03.03.04v.03s-.25.21-.25.21c-.05.05-.12.13-.21.22-.06.1-.11.17-.15.23l-.43.63-.25.4-.05.09-.28.4s-.01.02-.03,0c-.02,0-.03-.02-.03-.04l.03-.16h.03c.03.06.06.05.07-.01.01-.06.03-.1.06-.12.02-.08.07-.2.14-.36v-.03c.02-.06.08-.15.19-.25l.08-.08s.02-.04.05-.06c.03-.04.05-.05.08-.05.02,0,.04-.01.04-.06v-.03c.02-.08.09-.18.2-.29.12-.24.26-.47.44-.69.09-.11.14-.18.14-.2l.17-.32c.03-.06.07-.13.11-.21.04-.1.09-.17.14-.2.03-.06.06-.12.07-.18.04-.08.08-.13.13-.17v-.06s-.05,0-.06.02c-.02,0-.03,0-.04.02-.02.1-.07.19-.15.26-.08.07-.14.12-.17.16l-.1.14c-.02.08-.06.12-.12.1-.06-.01-.1.02-.12.1,0,.02-.02.04-.05.06-.02.02-.05.02-.07.02l-.08.08c-.39.61-.72,1.08-.99,1.39l-.31.39s-.02.03-.04.02l-.02-.04s0-.08-.01-.1c.07-.12.13-.2.19-.25.14-.25.23-.42.27-.5v-.03s-.03.02-.03.02l-.18.22c-.13.08-.24.19-.33.32,0,0,0,0-.03,0,0,0,0,.01,0,.03v-.03s-.01-.07-.01-.07v.06c-.1.09-.21.23-.33.42l-.07.02s.02,0,0-.03c0,0,0,0,.03,0,.07-.12.11-.21.12-.27.05-.05.12-.16.2-.32v-.03c.08-.05.14-.12.19-.22.07-.12.12-.19.15-.23v-.06s.03-.06.03-.06l-.07.02c-.04.1-.14.22-.28.37-.03.04-.06.07-.09.11-.03.02-.05.04-.08.08-.05.03-.08.05-.08.05l.02-.09.18-.22c.03-.06.07-.12.1-.17.04-.08.08-.15.11-.21l.13-.17c.05-.03.06-.06.02-.09-.02,0-.03,0-.03,0,0-.02,0-.03,0-.03l.18-.22v-.03s-.02,0-.02,0l-.08.08-.04.02v-.06s.11-.13.21-.29l.69-.9.53-.8c.05-.05.1-.13.15-.23.07-.12.12-.2.15-.26.18-.22.31-.4.38-.54.06-.1.14-.2.23-.31.11-.13.19-.24.24-.34.3-.37.51-.65.64-.84.21-.26.38-.51.52-.74.05-.12.12-.24.21-.35.12-.13.19-.22.22-.28l.67-.97.4-.5s.06-.07.09-.11c.03-.06.06-.12.07-.18.3-.37.49-.66.58-.86l.19-.25c.03-.06.08-.12.14-.2.06-.1.12-.19.16-.29l.56-.76c.07-.12.25-.33.53-.64.11-.2.17-.3.2-.32.05-.05.04-.09-.04-.11l-.25-.05c-.43-.05-.76-.08-1-.08-.34-.03-.62-.05-.84-.05-.32-.05-.72-.05-1.21,0-.26,0-.5.03-.7.08-.2.02-.37.04-.5.06l-1.11.12s-.05.03-.08.05c-.17-.04-.34-.03-.53.02-.16.05-.29.09-.38.11-.19.09-.34.15-.43.17-.05.03-.08.05-.08.05-.02.02-.06.02-.1.01.02,0,.03-.01.04-.06l.34-.19.51-.22s.06-.03.11-.04c.05-.01.07-.03.08-.05l.26-.14.04-.02.61-.23.14-.04s.06,0,.11-.04c.02,0,.03,0,.03,0,0-.02,0-.03,0-.03h.06s.09.02.13,0c.05-.03.1-.06.15-.07v-.03s-.02,0-.02,0l-.29-.03-.05-.04v-.06s.45-.2.45-.2l.05-.06.28-.07v-.03s-.02,0-.02,0h-.06s0,0,0,.02c0,0-.01,0-.03,0l-.11.04s-.01,0-.03,0c0,0,0-.01,0-.03-.04,0-.06-.01-.06-.01l-.36.02s-.1.01-.16,0h-.03s.05-.06.05-.06h.13s.11-.08.11-.08l.04-.02c.11-.02.29-.07.52-.15h.03c.08.02.15.03.19.02.05-.03.18-.05.4-.04h.1s.05-.06.08-.06c.06.01.13.02.19,0,.07-.03.15-.03.23-.02h.03s.06.02.06.02c.02-.02.05-.02.07-.02.04,0,.07,0,.1-.01.02,0,.07-.02.15-.07.05-.03.08-.04.1-.01,0,.02,0,.03,0,.03.02,0,.03,0,.04-.02l.11-.07s0-.03-.03-.04l-.26-.02h-.81s-.08,0-.17.02h-.03s.04-.03.04-.03l.17-.03.04-.06s-.05.02-.07.02l-.09-.02s-.05-.04-.09-.05l-.53.02h-.03s.04-.03.04-.03l.4-.04h.36s.04-.01.04-.01h-.03s-.04-.02-.06-.02c0-.02,0-.02-.03,0-.06-.01-.12-.01-.16,0h-.06s.07-.03.07-.03c.23-.04.39-.06.5-.06l.07-.02h-.06c-.1-.04-.19-.04-.26-.04-.07,0-.14,0-.23-.02-.08-.02-.15-.02-.19,0-.07,0-.16,0-.29-.03v-.03s.43,0,.43,0c.02-.02.05-.02.07-.02.04,0,.07,0,.1-.01.16-.05.38-.08.64-.09.4-.02.64-.04.73-.04.02,0,.03,0,.04-.02h-.06c-.07,0-.17,0-.3.02-.11,0-.21-.02-.31-.07-.02-.03-.04-.03-.06-.01,0,0,0,0-.03,0l.11-.04.14-.04c.19-.05.38-.06.6-.03.22,0,.36,0,.43,0h.4s.1-.02.1-.02c.09-.02.17-.03.23-.02.26,0,.42-.02.47-.03h.16s.16.04.16.04h.06s.1,0,.1,0l-.09-.05-.39-.15-.04.02.04-.02.41.09.19.04.04-.02s.08-.05.14-.04c.11-.02.28-.03.5-.02l.55.05c.22-.02.55-.02.99-.02.13-.01.37,0,.71.02.11-.02.26-.02.43,0,.18,0,.31,0,.4-.01.37,0,.7,0,.97.05.13,0,.25.01.36.01.13-.01.27-.02.4-.01.1.02.22.04.35.04.13-.01.26,0,.39.02l.4.12c.08.04.17.06.28.06l.17.1.14.1h.06c.07.09.17.16.29.21.12.05.2.08.24.09.04,0,.15.07.32.17.18.1.3.23.38.38.04.12.17.32.39.61.07.06.14.13.18.2.05.08.1.14.15.2,0,.02,0,.06.04.11.05.08.07.16.05.24l-.03.13c-.01.06-.05.08-.11.04-.02-.03-.05-.01-.11.04-.05.03-.08.07-.09.11,0,.04-.03.08-.06.12,0,.04,0,.09,0,.13.04.14.05.24.03.3-.02.08-.02.15,0,.19,0,.02,0,.13.03.33-.01.06-.07.08-.18.06l-.4-.28c-.06-.01-.12-.01-.16,0-.06-.01-.09-.03-.09-.05-.21-.24-.4-.4-.58-.49-.07-.06-.23-.11-.46-.16-.23-.07-.49-.11-.8-.11-.3-.02-.52-.04-.64-.04h-1.08s-.59,0-.59,0l-.09-.02.05.08.05.21c.03.05.05.08.05.08.11.18.11.34,0,.49l.03.04c0,.07-.01.12-.07.15-.05.01-.08.03-.11.04,0,.02-.02.03-.04.02-.02,0-.03,0-.03,0l-.19-.17-.09-.02s-.04.01-.04.06c-.06.05-.16.09-.32.1-.02,0-.07.02-.15.07-.03.04-.16.18-.39.44-.18.14-.38.35-.6.66l-.7.96-.67.81-.54.67c-.13.21-.26.4-.38.57-.12.15-.23.29-.32.42-.29.35-.46.57-.5.65-.03.04-.06.08-.1.14-.03.06-.07.12-.1.17l-.26.3c-.12.17-.2.28-.24.34l-.28.4-.42.56-.52.61c-.12.17-.24.32-.36.45-.09.13-.19.25-.27.37l-.7.8c-.17.27-.34.49-.51.68-.25.34-.42.6-.53.77-.04.06-.07.14-.12.24-.04.08-.1.17-.19.29-.06.1-.14.2-.23.31-.1.13-.19.26-.28.4l-.9,1.12-.26.47-.34.52c-.24.41-.38.7-.42.89l-.24.96-.05.51s-.02.03-.04.02v-.03s0-.01.01-.03c0,0-.01,0-.04.02v-.03s-.03,0-.03.02l-.04.06-.02-.07ZM149.11,43.65c.12-.15.2-.26.24-.34l.07-.02c-.06.05-.15.18-.28.37l-.04.06v-.06ZM149.42,43.3c.01-.06.01-.11,0-.13l.04-.06.02.07-.06.12ZM150.92,41.23l.12-.1-.02-.07s-.02.03-.04.02l-.1.14v.03s.03-.02.03-.02ZM150.77,29.02s.07,0,.08-.05c.06.01.11.01.13,0h.03s.26-.13.26-.13c.08-.05.19-.06.33-.03l.06.04h-.06s-.18.05-.18.05c-.04.06-.08.08-.15.07-.04,0-.1.01-.18.06l-.23.02s-.05.02-.07.02c0-.02,0-.03-.02-.04ZM152.23,28.65c.05-.03.09-.05.11-.04l-.02-.04-.11.04.02.04ZM152.73,27.67h.03s.26,0,.26,0h.03s-.04.03-.04.03c-.07,0-.15,0-.26-.02h-.03ZM157.69,47.77s-.03-.02-.02-.04l.11-.21.23-.44.26-.44.12-.1c.05-.03.07-.07.06-.12v-.03s.13-.14.13-.14v-.03s-.05-.04-.05-.04c0,0,.02-.02.08-.05.09,0,.13-.06.13-.17-.02-.03-.02-.05-.02-.07.02,0,.03,0,.04-.02.03-.04.06-.1.1-.17.06-.07.1-.14.11-.21.02-.1.08-.21.17-.32.09-.11.15-.2.19-.25.03-.06.17-.27.4-.63.02-.02.04-.06.06-.12h-.03c-.09.08-.14.14-.17.15-.07.03-.13.07-.19.12l-.13.17-.07.02s0-.01,0-.03c0,0,0,0,.03,0,.06-.07.14-.19.24-.34.1-.15.2-.28.31-.39.11-.11.2-.2.25-.27.07-.1.11-.17.15-.23v-.06s-.05-.01-.05-.01h-.03s.03,0,.03,0l.08-.21s.04-.07.02-.09c0-.02,0-.04.01-.06l.06-.28.04-.02s.08,0,.11-.04l.09-.11c.04-.1.13-.24.26-.44,0-.02.03-.05.08-.08.11-.11.18-.19.22-.25,0,0,0-.02.01-.06,0,0-.01,0-.03,0,0,0,0,.01,0,.03l-.13.17s-.01,0-.03,0c0,0,0,.01,0,.03v-.03s.12-.21.12-.21c.03-.06.06-.1.09-.11.03-.04.06-.06.08-.08v-.06s.04-.06.06-.06h.03s.11-.2.11-.2v-.06c.06-.01.1-.05.13-.1.04-.08.07-.13.1-.14v-.06s-.06.02-.06.02l-.24.18c-.06.05-.1.11-.13.17-.03.06-.07.11-.1.14,0,.04-.02.06-.05.06l-.04.06v-.06s-.02-.04-.04-.04c0,0,0,.01,0,.03-.02.02-.08.07-.16.16l-.34.35-.19.12v.03s0,.05-.02.06c0,0,0,.01,0,.03,0,0-.01,0-.03,0l-.41.37-.39.44-.29.3-.04.02v-.03c.15-.17.23-.27.24-.31l.14-.17.16-.16s.04-.05.05-.09c0,0,0-.01,0-.03v-.03s.1-.11.1-.11l.2-.19v-.03s-.03,0-.03,0l-.18.22c-.05.03-.09.05-.11.04,0,.02-.02.03-.04.02v-.03c.07-.07.12-.14.18-.19.06-.07.1-.13.13-.17l.51-.54.16-.13c.05-.03.11-.11.18-.22,0-.02,0-.03-.02-.04v.03s-.24.18-.24.18l-.66.64c-.05.03-.1.08-.16.13-.03.06-.09.11-.17.16l-.04.06h-.03s0-.04,0-.04l.28-.37c.07-.1.13-.17.21-.22l.18-.22.22-.28v-.03s-.03,0-.03,0c-.01.06-.04.09-.08.08l-.16.13s-.03.05-.08.08l-.38.38s-.01,0-.03,0c0,0,0,.01,0,.03v-.06s.07-.09.07-.09c.05-.03.08-.08.1-.14.01-.06.03-.1.06-.12.03-.04.06-.07.09-.11.14-.14.28-.3.43-.46.17-.18.35-.37.55-.57.06-.1.18-.21.34-.35v-.06s-.06,0-.09.01l-.13.14c-.14.12-.32.31-.55.57-.03.04-.06.08-.1.14-.03.04-.07.07-.12.1l-.13.14h-.03s0-.04,0-.04l.47-.52.22-.25v-.03s.02-.06.02-.06c.06-.07.11-.13.16-.16.05-.03.11-.12.19-.25.02,0,.03,0,.03,0,0-.02,0-.03,0-.03h-.06c-.09.01-.16.02-.2,0-.05.01-.09.01-.13,0-.02-.03-.03-.06-.04-.11-.05-.08-.11-.11-.17-.1-.08-.02-.18-.06-.3-.13,0,0-.02,0-.06-.01-.02-.03-.04-.02-.07.02,0,0,0,0-.03,0,0,0,0-.01,0-.03,0-.02,0-.03-.02-.04.03-.15-.02-.21-.15-.2-.09,0-.15-.02-.18-.07-.03-.07-.07-.15-.12-.22-.07-.1-.12-.2-.16-.3-.06-.12-.04-.26.06-.41.07-.12.11-.22.13-.3v-.06c-.04-.06-.03-.14.04-.26.09-.09.17-.14.26-.14.06.01.17,0,.31-.06.18-.14.36-.17.55-.11.08.02.17.02.26,0,.44-.03.77-.09.99-.18.14-.06.28-.06.4-.01l.09.02c.17.04.45.03.85-.01.03-.02.1-.06.22-.12.18-.24.36-.47.54-.67.18-.2.32-.38.44-.53l.52-.61.57-.83.45-.59s.15-.17.35-.38l.63-.78.37-.48.12-.1s0-.04.01-.06c.03-.02.03-.03,0-.03,0-.02-.02-.04-.09-.05-.09,0-.19,0-.29,0-.09,0-.18.02-.27.04l-.74.1-1.13.25-.07.02s-.07.06-.11.07c-.05.01-.08.03-.11.04-.07,0-.26.05-.58.14-.21.08-.34.13-.36.15l-.67.35-.07.02s.03,0,.03,0c0-.02,0-.03,0-.03l.36-.28.07-.02s0-.04.01-.06c.03-.02.03-.03,0-.03-.02-.03-.04-.03-.06-.01,0,0-.01,0-.03,0-.02.02-.06.02-.1.01.01-.06.03-.09.05-.09.05-.01.08-.06.1-.14l.09-.44c.01-.06.01-.11,0-.13-.02-.11-.09-.15-.21-.11h-.06s.03,0,.03,0c0-.02,0-.03,0-.03l.18-.09s.06,0,.11-.04c.02-.08.08-.11.18-.09.23-.06.38-.11.46-.16.02-.02.05-.02.07-.02.05-.01.1-.03.15-.07.09-.02.24-.08.43-.17.41-.17.71-.27.91-.29h.03s.03.01.03.01c0-.02,0-.03,0-.03h-.03c-.33-.08-.74-.09-1.21-.04l-.53.02h-.03s0-.04,0-.04c.02,0,.03,0,.03,0,.09-.02.31-.05.64-.09l.2-.02.36-.02c.07,0,.11-.02.14-.04.05-.01.08-.03.11-.04.14-.06.24-.07.3-.03.04.03.08.03.13,0l.11-.07v-.03s.06-.02.08-.02c.04,0,.08,0,.1-.01l.02.07h.03c.13,0,.25,0,.36.02l.11-.04s.07-.06.11-.07c.05-.01.08-.02.1-.01l.07-.02-.06-.04-.16-.03h-.33s-.06-.03-.06-.05h.03s.11,0,.19.02c.03-.02.06-.02.1-.01.08-.05.12-.05.13,0h.03s.08-.07.08-.07h-.03c-.13-.03-.23-.05-.32-.04l-.16-.03h-.03s.03-.01.04-.03h.06s.4,0,.4,0h.13c.13-.02.22-.02.26-.01h.29s.42.02.42.02c.03-.02.05-.01.06.01.02,0,.04,0,.07-.02.08.02.14,0,.17-.03.08-.05.13-.04.16.03,0,.02,0,.03.02.04.03-.02.04-.02.04-.02.05-.03.08-.03.09.02h.13s.33-.03.33-.03h.03s-.03,0-.03,0c-.12-.03-.21-.03-.26-.02h-.06s.04-.04.04-.04l.27-.04h.43c.09-.03.27-.04.53-.02.13-.01.31-.02.53-.02.07,0,.15-.01.26,0,.13,0,.23.02.29.03.24,0,.61.05,1.12.11.11,0,.27.03.48.07.38.08.7.23.99.44.31.18.56.35.74.52.28.23.5.47.67.7.12.16.27.41.46.75l.21.4.09.35c0,.18.02.3.05.37l.06.18c.02.09.04.21.06.34l-.07-.28-.02-.04v.03s0,.3,0,.3v.03c.03.05.04.11.02.17-.01.06-.02.11-.03.16l-.02.09s-.01.06-.03.13c-.01.06-.01.12,0,.16.01.05,0,.13-.02.26v.03s-.03-.04-.03-.04c-.03-.05-.04-.11-.03-.17.02-.08.03-.14.03-.16v-.06s-.03.06-.03.06l-.15.56c-.02.1-.12.27-.3.49-.13.19-.29.37-.48.55-.2.22-.53.5-1,.83l-.82.61-.39.28-.58.27-.18.09s-.1.02-.17.03c-.05.01-.11.04-.18.09l-.54.21c-.08.05-.21.1-.39.14-.09.02-.21.06-.35.12-.12.04-.26.09-.42.14l-.38.11c-.14.06-.35.12-.63.19l-.72.17c-.32.06-.56.1-.71.11l-1.11.15c-.11,0-.14.05-.1.14l.11.12.32.33s.08.12.14.26l.07.15.36.6.09.18.36.6.18.4c.09.19.17.34.23.44.02.03.06.04.12.06.05-.03.06-.08.03-.16-.02,0-.03,0-.03,0,0-.02,0-.03,0-.03,0,0,0,.01,0,.03.02,0,.03,0,.04-.02.04,0,.07,0,.07-.02v-.1s0-.06,0-.06l.02.07c.03.07.05.17.06.31,0,.04,0,.08.01.1.05.08.08.17.1.28.02.09.05.16.08.21l.09.18c.12.24.2.43.24.54l.33.73.19.47.13.32v.03c-.06.03-.08.05-.08.05-.12-.03-.17,0-.12.1l.19.47.39.9s.11.21.37.7c.02.03.02.06.01.1-.04,0-.07-.03-.09-.05-.15-.14-.24-.23-.27-.26-.12-.07-.18-.13-.19-.17l-.09-.02-.05.09s-.03,0-.04.02c.02.03.01.05-.01.06-.05.03-.05.09,0,.16l.12.22.02.04h-.06s-.07-.16-.07-.16c-.07-.1-.23-.26-.49-.47l-.2-.14s-.05-.04-.09-.05c0,.02-.02.03-.04.02,0,.02,0,.04.02.07l.13.32v.03s-.02,0-.04,0c0,0,0-.01,0-.03l-.35-.63-.12-.19s0,0-.03,0c0,0,0-.01,0-.03,0,.04-.01.06-.01.06.03.16.08.32.16.49,0,.04,0,.08.01.1-.03-.05-.05-.08-.05-.08-.03-.05-.06-.08-.08-.08v.1c.04.05.06.11.07.18.02.09.05.15.09.18.02,0,.03,0,.03,0,0,.02,0,.03,0,.03h-.03c-.03-.06-.06-.09-.08-.09h-.06c-.05.02-.12.03-.2,0,0,0-.02-.01-.06-.04-.04,0-.06,0-.04.06l-.04.02-.04-.11s-.04-.03-.06-.01c0-.02-.01-.04-.05-.04-.01-.05-.06-.1-.13-.16,0,0-.02,0-.06-.01,0,.02,0,.03.02.04l.05.24v.06s-.04-.04-.04-.04l-.19-.34h-.03s0,.02,0,.02v.1s.1.21.1.21v.03c-.06-.08-.11-.19-.17-.33-.02,0-.04-.02-.06-.04,0,0-.01,0-.04.02l-.06-.04-.1-.32c-.09-.19-.24-.49-.46-.89-.01-.05-.04-.11-.09-.18-.03-.05-.05-.11-.06-.18-.06-.1-.1-.15-.1-.15-.05-.06-.11-.15-.17-.3l-.1-.12-.28-.52-.36-.6-.59-.91-.43-.58-.39-.48-.37-.57-.23-.31-.23-.28c-.06-.03-.1-.03-.13,0l-.26.27-.68.74-.45.43-.72.76-.26.3s-.03,0-.04.02c-.03.15-.11.28-.25.4-.09.13-.21.26-.35.38l-.26.3c-.06.07-.14.15-.25.24-.08.09-.17.2-.27.33-.41.48-.71.84-.89,1.08l-.37.35c-.15.19-.33.47-.55.86l-.15.23v.03ZM158.17,45.84l.22-.28h.03s0,.04,0,.04l-.09.11-.13.14-.04.02v-.03ZM158.99,44.91l.14-.2.02.07-.13.14h-.03ZM159.07,44.56h-.03c.07-.12.14-.26.22-.42.03-.02.04-.05.05-.09s.03-.07.05-.09c0-.02.02-.03.04-.02v.06s-.02.03-.02.03c0-.02.02-.03.04-.02l.07-.02-.04.06s-.04.1-.1.17c-.02.02-.04.06-.06.12l-.04.06-.13.17-.04.06v-.06ZM159.46,43.83s.03-.07.05-.09l.14-.2s.04-.1.1-.17l.04-.02v.03c-.09.2-.19.36-.31.49,0,0,0,0-.03,0,0,0,0,.01,0,.03v-.06ZM159.55,43.98s.04-.06.06-.12c.03-.02.05-.03.08-.05.03-.04.06-.08.1-.14.03-.02.05-.03.08-.05.03-.04.06-.08.1-.14h.03s-.1.15-.1.15l-.25.24s-.04.08-.09.11ZM159.81,43.25s.02-.06.04-.06c0-.04.04-.06.08-.05,0,.04-.02.06-.04.06,0,.04-.02.06-.04.06h-.03ZM160.16,43.75l.09-.11s.04-.03.04-.06c0-.02,0-.03-.02-.04-.04,0-.08,0-.1.01-.01.06-.03.1-.06.12v.03s.01.07.01.07l.04-.02ZM160.03,43l.04-.06.05.08s-.02.06-.04.06l-.15.07.1-.14ZM160.24,43.24s.05-.03.08-.05c.03-.04.05-.08.06-.12.07-.14.12-.21.15-.23.02,0,.03,0,.03,0,0-.02,0-.03,0-.03-.01-.05,0-.08.02-.09.05-.03.09-.06.11-.07l.02-.09-.08.05-.04.02-.32.42s-.04.05-.05.09c0,.02-.02.04-.04.06l.02.07.04-.02ZM161.67,40.7c.05-.03.08-.06.08-.08l-.02-.04c-.05.03-.08.05-.08.05l.02.07ZM169.77,45.92s0-.03,0-.03c.02,0,.03,0,.03,0,.03.05.05.08.05.08l-.04.06-.04-.11ZM169.6,45.07l-.05-.21c.02.09.05.16.08.21h-.03ZM169.54,44.86c-.05-.08-.1-.19-.16-.33l-.22-.51v-.03s.04.02.03.04l.13.29.19.47.02.07ZM168.05,41.92s-.03-.02-.02-.04c-.05-.08-.11-.13-.19-.17-.02-.03-.02-.05-.02-.07,0-.04,0-.08-.01-.1l.11-.04s.03.05.05.08c.02.03.02.05.02.07,0,.02.01.1.05.24.02,0,.03.02.02.04ZM167.4,29.76c.05-.03.1-.04.14-.04.04,0,.07.02.09.02,0-.02.02-.03.04-.02l-.02-.04s-.1,0-.16,0c-.05.01-.08.03-.11.04l.02.04ZM168.03,36.41c.09-.02.15-.03.17-.03l.59-.17c.46-.12.8-.22,1.02-.3l1.06-.36c.12-.04.21-.07.28-.1.1-.04.18-.08.25-.11l.65-.28c.35-.23.63-.39.82-.48.32-.17.65-.42.98-.74l.36-.31.04-.06s.01-.05.02-.09c.03-.06.08-.11.13-.17.07-.1.07-.18.02-.26-.02,0-.03,0-.03,0,0-.02,0-.03,0-.03,0-.09-.03-.15-.09-.18l-.37-.24-.1-.12s-.02-.05-.02-.07c0-.02,0-.03-.02-.04l-.32-.17-.26-.15-.12-.06.17-.03h.03s.03.01.03.01h-.03s-.12-.07-.24-.09l-.29-.03c-.15-.03-.25-.02-.3.03l-.04.02c-.09,0-.21.05-.36.15l-.39.31c-.25.16-.45.35-.58.56-.23.26-.37.4-.42.43-.03.04-.06.06-.08.08-.02,0-.05-.02-.09-.05l-.11-.09c-.15.1-.23.15-.23.15l-.46.78c-.18.31-.35.57-.53.77l-.26.27-.91,1.05-.17.16s-.01,0-.04.02c0,.02,0,.03.02.04,0,.04.01.05.06.01l.14-.04ZM170.52,33.22s.06,0,.07-.02c.03-.02.05-.06.06-.12.04-.06.08-.09.12-.1,0-.02,0-.03-.02-.04,0,0-.01,0-.03,0,0,0,0,.01,0,.03l-.2.19s-.02.03-.04.02l.06.04ZM176.06,35.14l.05-.09v.13s-.06-.01-.06-.01c0,.02-.02.03-.04.02l.04-.06ZM176.28,33.97s-.01,0-.03,0c0,0,0-.01,0-.03l.02-.23s.03.07.03.14c0,.07,0,.11,0,.13h-.03ZM175.56,48.58c-.1-.02-.19-.08-.26-.19l-.12-.06c-.15-.03-.26-.11-.34-.24-.08-.04-.14-.1-.19-.17-.07-.08-.17-.13-.29-.16-.02.02-.07,0-.12-.03-.06-.03-.11-.06-.15-.07l-.37-.28c-.1-.22-.24-.39-.41-.51-.11-.09-.2-.14-.26-.15-.1-.02-.16-.1-.18-.23-.03-.07-.14-.17-.33-.3-.15-.1-.3-.32-.45-.65-.03-.07-.08-.31-.17-.72-.01-.13,0-.25.04-.35h-.03s.17-.33.17-.33c.08-.16.12-.27.14-.33l.12-.24c.05-.03.1-.09.13-.17.04-.08.06-.13.07-.15-.05-.08-.06-.13-.03-.17.06-.05.09-.09.09-.11.05-.14.13-.26.24-.34.1-.15.2-.34.32-.55.04-.1.14-.24.29-.43.06-.07.24-.31.54-.7.11-.19.21-.35.3-.46.09-.13.17-.25.24-.34.14-.14.28-.32.41-.53.13-.08.21-.21.24-.37l.06-.12.14-.2s.04,0,.07-.02c.03-.02.04-.03.04-.06l.08-.08c.24-.3.38-.49.42-.56.12-.13.22-.25.31-.36.1-.13.17-.24.23-.31l.36-.45c.03-.06.1-.16.2-.32.1-.15.2-.28.31-.39.14-.17.24-.31.29-.43l.29-.46c.08-.07.14-.13.17-.19.04-.08.07-.14.1-.17.01-.06.07-.15.15-.26.05-.01.06-.04.05-.09.01-.06.01-.11,0-.13l-.16-.17s0-.04-.02-.07c0-.04.03-.07.05-.09.02-.1.02-.18-.01-.23v-.06s.04-.13.04-.13c-.01-.15.05-.23.18-.22.05-.03.13-.06.25-.08.27-.05.51-.14.71-.27.04,0,.07-.02.08-.08l.4-.67s.04-.08.03-.13c0-.04.03-.09.07-.15.03-.04.08-.1.14-.2.09-.11.18-.18.27-.2.18-.11.38-.15.61-.1.21.05.36.09.46.13.1.04.19.13.27.26.06.03.11.08.17.13.05.06.11.1.17.13.01.05.05.1.13.16.1.06.16.11.2.14l.23.28c.03.05.08.08.14.1.22-.02.4-.05.55-.11.48-.11.94-.19,1.36-.23.33-.1.65-.17.96-.19.29-.05.52-.05.69-.01l.22.05.28.06s.07.03.15.07c.08.02.14.06.17.13.02.03.05.04.09.05.04,0,.08.03.12.06.02.03.04.04.09.05.02,0,.03.02.02.04h-.03s-.04,0-.07.01c0,.02,0,.03,0,.03l.02.07-.04.02v.1s.22.08.22.08c0,0,.02.03.05.08.02.03.03.06.04.11.02.03.03.07.04.14-.01.06,0,.11.04.14.04.03.06.06.08.08.02,0,.04.06.06.18.04.03.06.06.08.08.04.03.06.06.08.08.07.1.07.2,0,.29-.03.13-.06.22-.09.27v.19c0,.09-.02.17-.06.25l-.17.36-.14.2h-.06c-.03-.06-.02-.13.04-.2.03-.02.04-.05.05-.09.01-.06.01-.11,0-.13-.01-.05-.02-.09-.04-.14-.01-.05-.06-.08-.14-.1-.02,0-.04.01-.04.06l-.04.06v-.06s0-.07,0-.13l-.19-.04-.09-.02c-.06-.03-.14-.05-.25-.05-.32.06-.55.1-.71.11-.27.05-.68.12-1.22.19-.44.03-.77.07-.97.12-.11.02-.28.05-.51.09-.22.02-.41.02-.56.01-.07,0-.15.02-.24.05-.07,0-.15.02-.24.05-.13.01-.2.02-.2.02-.13.01-.24.01-.33,0-.02.02-.07.03-.14.04-.06-.01-.1,0-.1.01l-.1.14-.38.57c-.06.07-.15.18-.26.3-.09.11-.17.23-.24.34-.15.19-.26.34-.33.45-.09.11-.19.22-.3.33-.09.11-.18.23-.28.37l-.13.14v.03s.06.01.06.01l.41-.08c.13,0,.24.03.34.07.04.03.16.07.37.11.06.01.1.05.1.12.02.03.04.04.09.05.17.1.28.16.32.17v.06s-.04,0-.04,0c-.02,0-.03,0-.04.02,0,.02-.02.03-.04.02.02,0,.03.02.02.04,0,.02,0,.03.02.04l.21.08h.03s.11.13.11.13l-.14.04c-.08-.02-.14-.02-.16,0h-.03s0,.03.02.03l.09.05.31.07s.1.04.18.1c.02.11.06.19.12.22l.18.07c.06.03.08.07.07.11,0,.02-.02.03-.04.02l-.24-.12h-.06s.03,0,.02.02c0,.07.04.13.09.18.08.04.14.07.18.1l.23.31s0,.01,0,.03c0,0,.01,0,.03,0l-.09-.02s0-.03-.02-.04c-.02,0-.03,0-.03,0,0-.09-.02-.11-.05-.08-.03.02-.05.02-.07.02v.13s.13.16.13.16c0,0,0,.01,0,.03.02.03.04.04.06.04-.04,0-.08-.04-.11-.09h-.03s-.02-.01-.06-.02v.1c.17.08.27.15.32.23l.11.25.05.08s.03.06-.02.09c-.02.02-.06.02-.1.01l-.17-.13-.26-.15c-.07-.06-.1-.03-.08.08v.03s-.03-.04-.03-.04c-.01-.05-.06-.07-.15-.07l-.99.02-.92.03-.27.04c-.33.02-.65.02-.95.02-.11,0-.22,0-.33.03-.11,0-.24,0-.39-.02-.04,0-.12,0-.23.02-.11,0-.21-.01-.32-.04l-.11.04c-.17.27-.29.44-.37.51l-.16.13c-.18.22-.38.49-.6.79-.09.11-.18.24-.28.4-.07.14-.18.28-.32.42-.34.54-.54.89-.62,1.05-.04.08-.08.17-.12.27-.04.08-.07.18-.1.31-.04.08-.01.12.07.11.07-.03.13-.04.17-.03.07,0,.11,0,.13,0h.03s-.03.01-.04.03l-.35.09s-.04,0-.07.02c0,0-.01,0-.03,0l.12.03.26.02h.06s-.04.04-.04.04l-.3.03c-.07,0-.12.03-.15.07-.02.02-.03.06-.03.13,0,.02,0,.04-.01.06.02,0,.03.02.02.04,0,.04.03.07.11.09l.26.02c.07,0,.14-.01.23-.02.11-.02.22-.02.33,0h.06s.04.02.06.03c.04,0,.07.03.09.05.07.1.13.14.21.11l1.04-.1.44-.07h.06s.11.02.2,0c.09-.02.18-.04.27-.04.05-.01.11-.03.21-.05.12-.04.23-.06.34-.06.02,0,.17-.02.44-.07.13-.01.24-.04.31-.06.09-.02.17-.04.24-.05.17.02.26.01.26,0l.04-.06s.03.02.03.04c0,.02,0,.03,0,.03.08-.05.1-.03.09.05.02.03.04.04.06.04.04,0,.07,0,.07-.02h.03s.06.02.06.02v-.03s.02-.06.02-.06c0-.02.02-.03.04-.02v.03s-.03.09-.03.09c0,0-.02.02-.08.05v.06s-.02.04-.03.06c.02,0,.03.02.03.04.02.03.07.08.16.17.02,0,.03.02.03.04.05.18.1.28.16.3.02,0,.03,0,.04-.02.02-.02.05-.02.07-.02l.04-.02s0,.01,0,.03c.02,0,.04,0,.06.01v.03s-.03.13-.03.13c.02,0,.06,0,.11-.04.05-.03.08-.06.08-.08,0,0,0-.01,0-.03.03-.02.04-.03.04-.06.02,0,.03.02.03.04,0,.02,0,.03.02.04v.03c-.06.03-.08.08-.07.15.02.03.02.07,0,.13.02.11.07.16.17.13.07,0,.12,0,.16.03.04.1.02.2-.07.31-.1.04-.14.11-.14.2,0,.09,0,.14,0,.16l-.07.31-.04.02s0,0-.03,0c-.02,0-.03-.02-.02-.04-.06-.03-.09-.09-.1-.15-.01-.05-.03-.06-.06-.04-.11.11-.27.16-.49.16-.11.02-.25.03-.4.04-.13.01-.28.04-.44.07-.13.01-.28.05-.45.1h-.03s-.08-.04-.13,0c-.05.03-.09.05-.11.04l-.04.02-.12-.03c-.03.06-.08.09-.15.1-.07,0-.11,0-.13,0h-.19c-.13,0-.25.07-.34.18h-.03c-.06-.02-.15-.02-.26,0-.11.02-.2.03-.27.04l-.28.07s-.06,0-.11.04c-.06-.01-.09-.02-.09-.02h-.06c-.06-.03-.14-.02-.23,0-.1.04-.18.07-.25.08l-.14.07-.24.05-.09-.02ZM175.16,46.04l.08-.05h-.06c-.06-.03-.11-.02-.14.02l-.04.02h.06s.1,0,.1,0ZM173.85,43.27l.06-.12s0-.03-.02-.04v.03s-.05.06-.07.12h.03ZM175.46,45.97c.1.02.18.03.23.02h.03s-.02-.03-.02-.03l-.23.02h-.03s0,0,0,.02c.02,0,.03,0,.04-.02ZM174.11,42.83c.05-.03.08-.08.1-.14v-.03s-.02,0-.02,0l-.09.11v.06s.02,0,.02,0ZM177.75,47.06s.05-.05.08-.05c.02,0,.04,0,.07-.02l.38-.08c.06.01.14,0,.23-.02l.04-.06-.07.02c-.22,0-.38.01-.5.06-.05.03-.12.06-.21.08-.02,0-.04.01-.04.06h.03ZM177.88,46.46c.14-.04.28-.06.41-.08.13-.01.25-.03.34-.06l.07-.02s-.06-.01-.06-.01l-.43.04s-.1.03-.18.06c-.05.01-.11.03-.18.06h-.03s.03,0,.03,0h.03ZM179.05,46.19c.16-.01.28-.04.38-.08l.12.03-.15-.07c-.14.06-.26.09-.35.09,0,0,0,.01,0,.03,0,0-.01,0-.03,0h.03ZM187.33,35.61v-.06c.03-.06.05-.1.07-.12h.03s-.08.22-.08.22h-.03s0-.04,0-.04ZM190.34,54.82s-.03-.02-.02-.04l.11-.21.23-.44.26-.44.12-.1c.05-.03.07-.07.06-.12v-.03s.13-.14.13-.14v-.03s-.05-.04-.05-.04c0,0,.02-.02.08-.05.09,0,.13-.06.13-.17-.02-.03-.02-.05-.02-.07.02,0,.03,0,.04-.02.03-.04.06-.1.1-.17.06-.07.1-.14.11-.21.02-.1.08-.21.17-.32.09-.11.15-.2.19-.25.03-.06.17-.27.4-.63.02-.02.04-.06.06-.12h-.03c-.09.08-.14.14-.17.15-.07.03-.13.07-.19.12l-.13.17-.07.02s0-.01,0-.03c0,0,0,0,.03,0,.06-.07.14-.19.24-.34.1-.15.2-.28.31-.39.11-.11.2-.2.25-.27.07-.1.11-.17.15-.23v-.06s-.05-.01-.05-.01h-.03s.03,0,.03,0l.08-.21s.04-.07.02-.09c0-.02,0-.04.01-.06l.06-.28.04-.02s.08,0,.11-.04l.09-.11c.04-.1.13-.24.26-.44,0-.02.03-.05.08-.08.11-.11.18-.19.22-.25,0,0,0-.02.01-.06,0,0-.01,0-.03,0,0,0,0,.01,0,.03l-.13.17s-.01,0-.03,0c0,0,0,.01,0,.03v-.03s.12-.21.12-.21c.03-.06.06-.1.09-.11.03-.04.06-.06.08-.08v-.06s.04-.06.06-.06h.03s.11-.2.11-.2v-.06c.06-.01.1-.05.13-.1.04-.08.07-.13.1-.14v-.06s-.06.02-.06.02l-.24.18c-.06.05-.1.11-.13.17-.03.06-.07.11-.1.14,0,.04-.02.06-.05.06l-.04.06v-.06s-.02-.04-.04-.04c0,0,0,.01,0,.03-.02.02-.08.07-.16.16l-.34.35-.19.12v.03s0,.05-.02.06c0,0,0,.01,0,.03,0,0-.01,0-.03,0l-.41.37-.39.44-.29.3-.04.02v-.03c.15-.17.23-.27.24-.31l.14-.17.16-.16s.04-.05.05-.09c0,0,0-.01,0-.03v-.03s.1-.11.1-.11l.2-.19v-.03s-.03,0-.03,0l-.18.22c-.05.03-.09.05-.11.04,0,.02-.02.03-.04.02v-.03c.07-.07.12-.14.18-.19.06-.07.1-.13.13-.17l.51-.54.16-.13c.05-.03.11-.11.18-.22,0-.02,0-.03-.02-.04v.03s-.24.18-.24.18l-.66.64c-.05.03-.1.08-.16.13-.03.06-.09.11-.17.16l-.04.06h-.03s0-.04,0-.04l.28-.37c.07-.1.13-.17.21-.22l.18-.22.22-.28v-.03s-.03,0-.03,0c-.01.06-.04.09-.08.08l-.16.13s-.03.05-.08.08l-.38.38s-.01,0-.03,0c0,0,0,.01,0,.03v-.06s.07-.09.07-.09c.05-.03.08-.08.1-.14.01-.06.03-.1.06-.12.03-.04.06-.07.09-.11.14-.14.28-.3.43-.46.17-.18.35-.37.55-.57.06-.1.18-.21.34-.35v-.06s-.06,0-.09.01l-.13.14c-.14.12-.32.31-.55.57-.03.04-.06.08-.1.14-.03.04-.07.07-.12.1l-.13.14h-.03s0-.04,0-.04l.47-.52.22-.25v-.03s.02-.06.02-.06c.06-.07.11-.13.16-.16.05-.03.11-.12.19-.25.02,0,.03,0,.03,0,0-.02,0-.03,0-.03h-.06c-.09.01-.16.02-.2,0-.05.01-.09.01-.13,0-.02-.03-.03-.06-.04-.11-.05-.08-.11-.11-.17-.1-.08-.02-.18-.06-.3-.13,0,0-.02,0-.06-.01-.02-.03-.04-.02-.07.02,0,0,0,0-.03,0,0,0,0-.01,0-.03,0-.02,0-.03-.02-.04.03-.15-.02-.21-.15-.2-.09,0-.15-.02-.18-.07-.03-.07-.07-.15-.12-.22-.07-.1-.12-.2-.16-.3-.06-.12-.04-.26.06-.41.07-.12.11-.22.13-.3v-.06c-.04-.06-.03-.14.04-.26.09-.09.17-.14.26-.14.06.01.17,0,.31-.06.18-.14.36-.17.55-.11.08.02.17.02.26,0,.44-.03.77-.09.99-.18.14-.06.28-.06.4-.01l.09.02c.17.04.45.03.85-.01.03-.02.1-.05.22-.12.18-.24.36-.47.54-.67.18-.2.32-.38.44-.53l.52-.61.57-.83.45-.59s.15-.17.35-.38l.63-.78.37-.48.12-.1s0-.04.01-.06c.03-.02.03-.03,0-.03,0-.02-.02-.04-.09-.05-.09,0-.19,0-.3,0-.09,0-.18.02-.27.04l-.74.1-1.13.25-.07.02s-.07.06-.11.07c-.05.01-.08.03-.11.04-.07,0-.26.05-.58.14-.21.08-.34.14-.36.15l-.67.35-.07.02s.03,0,.03,0c0-.02,0-.03,0-.03l.36-.28.07-.02s0-.04.01-.06c.03-.02.03-.03,0-.03-.02-.03-.04-.03-.06-.01,0,0-.01,0-.03,0-.03.02-.06.02-.1.01.01-.06.03-.09.05-.09.05-.01.08-.06.1-.14l.09-.44c.01-.06.01-.11,0-.13-.02-.11-.09-.15-.21-.11h-.06s.03,0,.03,0c0-.02,0-.03,0-.03l.18-.09s.06,0,.11-.04c.02-.08.08-.11.18-.09.23-.06.38-.11.46-.16.02-.02.05-.02.07-.02.05-.01.1-.03.15-.07.09-.02.24-.08.43-.17.41-.17.71-.27.91-.29h.03s.03.01.03.01c0-.02,0-.03,0-.03h-.03c-.33-.08-.74-.09-1.21-.04l-.53.02h-.03s0-.04,0-.04c.02,0,.03,0,.03,0,.09-.02.31-.05.64-.09l.2-.02.36-.02c.07,0,.11-.02.14-.04.05-.01.08-.03.11-.04.14-.06.24-.07.3-.03.04.03.08.03.13,0l.11-.07v-.03s.06-.02.08-.02c.04,0,.08,0,.1-.01l.02.07h.03c.13,0,.25,0,.36.02l.11-.04s.07-.06.11-.07c.05-.01.08-.02.1-.01l.07-.02-.06-.04-.16-.03h-.33s-.06-.03-.06-.05h.03s.11,0,.19.02c.03-.02.06-.02.1-.01.08-.05.12-.05.13,0h.03s.08-.07.08-.07h-.03c-.12-.03-.23-.05-.32-.04l-.16-.03h-.03s.03-.01.04-.03h.06s.4,0,.4,0h.13c.13-.02.22-.02.26-.01h.29s.42.02.42.02c.03-.02.05-.01.06.01.02,0,.04,0,.07-.02.08.02.14,0,.17-.03.08-.05.13-.04.16.03,0,.02,0,.03.02.04.03-.02.04-.02.04-.02.05-.03.08-.03.09.02h.13s.33-.03.33-.03h.03s-.03,0-.03,0c-.12-.03-.21-.03-.26-.02h-.06s.04-.04.04-.04l.27-.04h.43c.09-.03.27-.04.53-.02.13-.01.31-.02.53-.02.07,0,.15-.01.26,0,.13,0,.23.02.29.03.24,0,.61.05,1.12.11.11,0,.27.03.48.07.38.08.7.23.99.44.31.18.56.35.74.52.28.23.5.47.67.7.12.16.27.41.46.75l.21.4.09.35c0,.18.02.3.05.37l.06.18c.02.09.04.21.06.34l-.07-.28-.02-.04v.03s0,.29,0,.29v.03c.03.05.04.11.02.17-.01.06-.02.11-.03.16l-.02.09s-.01.06-.03.13c-.01.06-.01.12,0,.16.01.05,0,.13-.02.26v.03s-.03-.04-.03-.04c-.03-.05-.04-.11-.03-.17.02-.08.03-.14.03-.16v-.06s-.03.06-.03.06l-.15.56c-.02.1-.12.27-.3.49-.13.19-.29.37-.48.55-.2.22-.53.5-1,.83l-.82.61-.39.28-.58.27-.18.09s-.1.02-.17.03c-.05.01-.11.04-.18.09l-.54.21c-.08.05-.21.1-.39.14-.09.02-.21.06-.35.12-.12.04-.26.09-.42.14l-.38.11c-.14.06-.35.12-.63.19l-.72.17c-.32.06-.56.1-.71.11l-1.11.15c-.11,0-.14.05-.1.14l.11.12.32.33s.08.12.14.26l.07.15.36.6.09.18.36.6.18.4c.09.19.17.34.23.44.02.03.06.04.12.06.05-.03.06-.08.03-.16-.02,0-.03,0-.03,0,0-.02,0-.03,0-.03,0,0,0,.01,0,.03.02,0,.03,0,.04-.02.04,0,.07,0,.07-.02v-.1s0-.06,0-.06l.02.07c.03.07.05.17.06.31,0,.04,0,.08.01.1.05.08.08.17.1.28.02.09.05.16.08.21l.09.18c.12.24.2.43.24.54l.33.73.19.47.13.32v.03c-.06.03-.08.05-.08.05-.12-.03-.17,0-.12.1l.19.47.39.9s.11.21.37.7c.02.03.02.06.01.1-.04,0-.07-.03-.09-.05-.14-.14-.24-.23-.27-.26-.12-.07-.18-.13-.19-.17l-.09-.02-.05.09s-.03,0-.04.02c.02.03.01.05-.01.06-.05.03-.05.09,0,.16l.12.22.02.04h-.06s-.07-.16-.07-.16c-.07-.1-.23-.26-.49-.47l-.2-.14s-.04-.04-.09-.05c0,.02-.02.03-.04.02,0,.02,0,.04.02.07l.13.32v.03s-.02,0-.04,0c0,0,0-.01,0-.03l-.35-.63s-.04-.06-.12-.19c0,0,0,0-.03,0,0,0,0-.01,0-.03,0,.04-.01.06-.01.06.03.16.08.32.16.49,0,.04,0,.08.01.1-.03-.05-.05-.08-.05-.08-.03-.05-.06-.08-.08-.08v.1c.04.05.06.11.07.18.02.09.05.15.09.18.02,0,.03,0,.03,0,0,.02,0,.03,0,.03h-.03c-.03-.06-.06-.08-.08-.09h-.06c-.05.02-.12.03-.2,0,0,0-.02-.01-.06-.04-.04,0-.06,0-.04.06l-.04.02-.04-.11s-.04-.03-.06-.01c0-.02-.01-.04-.06-.04-.01-.05-.06-.1-.13-.16,0,0-.02,0-.06-.01,0,.02,0,.03.02.04l.05.24v.06s-.04-.04-.04-.04l-.19-.34h-.03s0,.02,0,.02v.1s.1.21.1.21v.03c-.06-.08-.11-.19-.17-.33-.02,0-.04-.02-.06-.04,0,0-.01,0-.04.02l-.06-.04-.1-.32c-.09-.19-.24-.49-.46-.89-.01-.05-.04-.11-.09-.18-.03-.05-.05-.11-.06-.18-.06-.1-.1-.15-.1-.15-.05-.06-.11-.15-.17-.3l-.1-.12-.28-.52-.36-.6-.59-.91-.43-.58-.39-.48-.37-.57-.23-.31-.23-.28c-.06-.03-.1-.03-.13,0l-.26.27-.68.74-.45.43-.72.76-.26.3s-.03,0-.04.02c-.03.15-.11.28-.25.4-.09.13-.21.26-.35.38l-.26.3c-.06.07-.14.15-.25.24-.09.09-.18.2-.27.33-.41.48-.71.84-.89,1.08l-.37.35c-.15.19-.33.47-.55.86l-.15.23v.03ZM190.82,52.89l.22-.28h.03s0,.04,0,.04l-.09.11-.13.14-.04.02v-.03ZM191.65,51.96l.14-.2.02.07-.13.14h-.03ZM191.72,51.61h-.03c.07-.12.14-.26.22-.42.03-.02.04-.05.05-.09,0-.04.03-.07.05-.09,0-.02.02-.03.04-.02v.06s-.02.03-.02.03c0-.02.02-.03.04-.02l.07-.02-.04.06s-.04.1-.1.17c-.03.02-.04.06-.06.12l-.04.06-.13.17-.04.06v-.06ZM192.11,50.88s.03-.07.05-.09l.14-.2s.04-.1.1-.17l.04-.02v.03c-.09.2-.19.36-.31.49,0,0,0,0-.03,0,0,0,0,.01,0,.03v-.06ZM192.21,51.03s.04-.06.06-.12c.03-.02.05-.03.08-.05.03-.04.06-.08.1-.14.03-.02.05-.03.08-.05.03-.04.06-.08.1-.14h.03s-.1.15-.1.15l-.25.24s-.04.08-.09.11ZM192.46,50.3s.02-.06.04-.06c0-.04.04-.06.08-.05,0,.04-.02.06-.04.06,0,.04-.02.06-.04.06h-.03ZM192.81,50.8l.09-.11s.04-.03.04-.06c0-.02,0-.03-.02-.04-.04,0-.08,0-.1.01-.01.06-.03.1-.06.12v.03s.01.07.01.07l.04-.02ZM192.68,50.05l.04-.06.05.08s-.02.06-.04.06l-.15.07.1-.14ZM192.89,50.3s.05-.03.08-.05c.03-.04.05-.08.06-.12.07-.14.12-.21.15-.23.02,0,.03,0,.03,0,0-.02,0-.03,0-.03-.01-.05,0-.08.02-.09.05-.03.09-.06.11-.07l.02-.09-.08.05-.04.02-.32.42s-.04.05-.05.09c0,.02-.02.04-.04.06l.02.07.04-.02ZM194.32,47.76c.05-.03.08-.06.08-.08l-.02-.04c-.05.03-.08.05-.08.05l.02.07ZM202.43,52.98s0-.03,0-.03c.02,0,.03,0,.03,0,.03.05.05.08.05.08l-.04.06-.04-.11ZM202.25,52.12l-.05-.21c.02.09.05.16.08.21h-.03ZM202.2,51.91c-.05-.08-.1-.19-.16-.33l-.22-.51v-.03s.03.02.03.04l.13.29.19.47.02.07ZM200.7,48.97s-.03-.02-.02-.04c-.05-.08-.11-.13-.19-.17-.02-.03-.02-.05-.02-.07,0-.04,0-.08-.01-.1l.11-.04s.03.05.05.08c.02.03.02.05.02.07,0,.02.01.1.05.24.02,0,.03.02.02.04ZM200.06,36.82c.05-.03.1-.04.14-.04.04,0,.07.02.09.02,0-.02.02-.03.04-.02l-.02-.04s-.1,0-.16,0c-.05.01-.08.03-.11.04l.02.04ZM200.68,43.47c.09-.02.15-.03.17-.03l.59-.17c.46-.12.8-.22,1.01-.3l1.06-.36c.12-.04.21-.07.28-.1.1-.04.18-.08.25-.11l.65-.28c.35-.23.63-.39.82-.48.32-.17.65-.42.98-.74l.36-.31.04-.06s.01-.05.02-.09c.04-.06.08-.11.14-.17.06-.1.07-.18.02-.26-.02,0-.03,0-.03,0,0-.02,0-.03,0-.03,0-.09-.03-.15-.09-.18l-.37-.24-.1-.12s-.02-.05-.02-.07c0-.02,0-.03-.02-.04l-.32-.17-.26-.15-.12-.06.17-.03h.03s.03.01.03.01h-.03s-.12-.06-.24-.09l-.29-.03c-.15-.03-.25-.02-.3.03l-.04.02c-.09,0-.21.05-.36.15l-.39.31c-.25.16-.45.35-.58.56-.23.26-.37.4-.42.43-.03.04-.06.06-.08.08-.02,0-.05-.02-.09-.05l-.11-.09c-.15.1-.23.15-.23.15l-.46.78c-.18.31-.35.57-.53.77l-.26.27-.91,1.05-.17.16s-.01,0-.04.02c0,.02,0,.03.02.04,0,.04.01.05.06.01l.14-.04ZM203.17,40.27s.07,0,.07-.02c.03-.02.05-.06.06-.12.04-.06.08-.09.12-.1,0-.02,0-.03-.02-.04,0,0-.01,0-.03,0,0,0,0,.01,0,.03l-.2.19s-.02.03-.04.02l.06.04ZM208.72,42.19l.05-.09v.13s-.06-.01-.06-.01c0,.02-.02.03-.04.02l.04-.06ZM208.94,41.03s-.01,0-.03,0c0,0,0-.01,0-.03l.02-.23s.03.07.03.14c0,.07,0,.11,0,.13h-.03ZM204.24,58.51s.05-.04.08-.08c.03-.02.05-.05.09-.11.02-.02.09-.15.18-.39.03-.02.04-.05.05-.09,0-.04.03-.07.05-.09.04-.17.04-.3.02-.39-.02-.03,0-.06.02-.09.03-.04.05-.07.05-.09.08-.05.12-.09.13-.14l.24-.34s.03-.07.05-.09l-.11.04s-.03,0-.03,0c.02.03.01.04,0,.03,0,.02-.02.03-.04.02v-.03s0-.05-.06-.01c-.05.03-.08.05-.08.05,0-.04.03-.07.05-.09.41-.37.61-.56.61-.56l.11-.21.16-.16.2-.19.13-.14h.03s0,.04,0,.04l-.12.1c-.08.05-.12.08-.12.1v.06s.06-.02.06-.02l.05-.09c.24-.19.37-.3.4-.34.03-.02.04-.05.05-.09l.04-.06-.07.02h-.03s.03,0,.03,0c.22-.3.42-.53.61-.69.08-.05.15-.14.22-.28.03-.02.04-.03.04-.06,0-.04.03-.07.05-.09v-.03s-.02,0-.02,0l-.04.02c-.13.1-.25.21-.36.31-.1.09-.2.17-.29.27l-.25.24h-.03c-.03-.08-.05-.08-.06-.02l-.23.15-.07.02.04-.02s.04-.05.05-.09c.02,0,.03,0,.04-.02l-.07.02s-.05.03-.08.05c0,.02-.02.05-.05.09l-.11.07h-.03s.03-.08.05-.09l.2-.19.18-.22v-.03c.05-.01.08-.04.09-.08.03-.02.06-.03.11-.04.04,0,.09-.02.15-.1.05-.03.09-.05.11-.04,0-.04.04-.08.09-.11s.08-.06.08-.08c0-.04,0-.07-.05-.08h-.03s.04-.03.04-.03c0-.02,0-.03,0-.03.02,0,.03,0,.03,0-.01-.05,0-.1.07-.15.1-.15.16-.25.19-.29.34-.36.54-.57.59-.62,0,0,.04-.02.12-.07v-.06s-.06.02-.06.02l-.41.37-.48.39c-.11.09-.23.19-.36.31-.11.11-.24.23-.38.38-.04,0-.07,0-.08.05l.02-.09.04-.06-.07.02-.08.08-.04.02v-.03s.11-.17.11-.17l.41-.37v-.06s-.06.02-.06.02c-.3.26-.43.38-.4.34,0,0-.01,0-.03,0,0,0,0,.01,0,.03h-.03s0-.04,0-.04l.04-.06-.07.02-.32.26s-.01,0-.03,0c0,0,0,.01,0,.03v-.03s.1-.14.1-.14v-.03s-.03.02-.03.02h-.03s0-.04,0-.04l.08-.08.54-.54v-.03s.02-.06.02-.06l-.07.02s-.05.03-.15.1c-.03.04-.09.07-.18.09-.07,0-.11.02-.14.04h-.03s0-.04,0-.04l.25-.24.29-.3.26-.3c.13-.1.24-.2.32-.29.11-.11.21-.2.29-.27l.76-.79.43-.5s.06-.08.1-.14c.06-.05.11-.11.17-.16.13-.1.23-.21.3-.33.16-.14.29-.28.38-.41l.59-.59c.12-.15.17-.26.14-.33,0-.09,0-.19,0-.3,0-.13,0-.27-.04-.43l-.03-.17-.03.13c-.01.15-.04.35-.1.6.02,0,.03.02.02.04,0,0,0,0-.03,0-.05.01-.06.08-.05.22l-.04.02v-.03s0-.26,0-.26l-.02-.04c-.04-.1-.06-.21-.06-.34,0-.15.01-.26,0-.33l-.06-1.09c0-.18-.01-.34-.02-.5.01-.17.02-.34.01-.52v-.56s0-.52,0-.52v-.26s.04-1,.04-1l.05-.84.03-.58c.01-.06.02-.18.01-.36,0-.11,0-.22,0-.33,0-.13,0-.25.01-.36.01-.26.01-.46,0-.59v-.16c.03-.13.13-.28.3-.46.05-.01.07-.04.08-.08.03-.04.06-.06.08-.08.12-.15.23-.24.32-.26l.47-.19.37-.21s.12-.03.21-.05c.12-.04.23-.05.33-.03.04.03.07.04.09.02.03-.02.05-.01.06.01.12.07.19.13.22.18l.12.03c.07,0,.14.02.21.08.13.11.27.18.42.19.03-.02.06,0,.09.02.06.03.1.05.12.06.03.05.05.08.05.08l.07-.02-.04.06c-.08.05-.12.14-.12.27.02.03.01.05-.01.06,0,0,0,.01,0,.03l-.03.13c-.05.12-.09.27-.13.46-.01.17-.03.31-.06.41-.02.1-.05.24-.09.41-.01.15-.02.33-.02.55-.02.21-.05.43-.07.64,0,.2,0,.4-.03.61l-.11,1.25-.09,1.03c-.01.26-.03.45-.06.58l.03.33.02.04s.03,0,.04-.02c.33-.32.5-.48.5-.48.23-.26.41-.45.55-.57.15-.19.28-.33.39-.44l.35-.42c.11-.11.26-.27.43-.5.03-.02.12-.1.29-.27l.14-.2.81-.87c.09-.11.18-.21.26-.3.11-.09.2-.16.28-.23.06-.1.13-.18.19-.25.08-.09.15-.16.21-.22.12-.15.23-.26.33-.32l.4-.47c.08-.07.17-.16.26-.27.11-.11.2-.19.28-.23l.38-.38c.08-.07.24-.12.46-.16.04,0,.07,0,.07-.02.17-.09.35-.1.53-.02.08.04.19.08.33.14.16.06.31.1.43.13.02,0,.05.03.08.08.11.11.19.17.25.19.11,0,.18.05.2.14.04.03.08.07.14.13.05.06.12.11.19.17,0,0,.02.04.07.11l.07.11.17.43v.03c-.03.1-.03.21-.01.33l-.02.09s0,.06.02.07c.05.06.05.11,0,.16-.03.06-.05.1-.06.12,0,.02-.04.02-.1.01h-.06c-.1-.04-.26.02-.46.15-.19.16-.39.34-.61.56l-.79.91c-.14.17-.27.31-.39.44-.12.13-.21.24-.3.33l-.56.63c-.18.14-.36.3-.54.51l-.26.27-.66.64-.79.78-.58.56c-.23.26-.41.45-.55.57l-.45.39c-.08.09-.32.3-.69.64-.18.2-.42.42-.73.66-.06.07-.13.14-.2.19-.05.03-.1.07-.15.1-.1.07-.13.15-.09.24.01.05,0,.11,0,.19v1.34c.02.13.02.23,0,.3v.03s-.03-.04-.03-.04l-.17-.56-.16-.3c-.01-.13-.02-.2-.02-.2h-.06s-.03,0-.04.01c0,.02,0,.03,0,.03l.13.16s-.06-.01-.06-.01h-.03c-.08-.02-.13-.07-.14-.13,0-.07-.02-.11-.04-.14,0-.04-.01-.05-.06-.01,0,0-.05.03-.15.1-.09.11-.18.2-.29.27l-.31.23c-.34.25-.55.44-.64.55l-.26.27s-.08.05-.09.11c-.02.08-.09.17-.22.25l-.04.02c-.06-.01-.12,0-.18.06-.05.03-.09.06-.11.07-.35.32-.54.48-.57.5l-.34.35-.62.62-.07.02c-.17.2-.37.41-.59.62l-.34.35c-.08.05-.15.1-.23.15-.06.07-.11.13-.17.16-.11.09-.22.19-.33.32-.1.13-.18.24-.27.33l-.52.58c-.08.07-.18.18-.3.33-.28.27-.43.42-.46.46,0,.04-.07.09-.2.15l-.32.26-.04.02v-.06ZM205.66,55.28s.04-.1.1-.17h.03s.03.02.02.04l-.16.13ZM206.01,55.16v-.03s.04-.05.09-.08h.03s-.11.08-.11.08v.03ZM206.37,54.71v-.06s-.06.02-.06.02h-.03s-.02.02-.04.02c0,.02.01.04.06.04l.07-.02ZM206.44,54.53l.04-.06.08-.05-.11.04s-.03-.02-.04.02l.02.07v-.03ZM207.54,53.56l-.06-.04c-.06-.01-.11.02-.15.1,0,0,0,.01,0,.03,0,0-.01,0-.03,0h-.03s.05.07.05.07l.23-.15ZM208.35,52.69s0-.03,0-.03c.03-.02.04,0,.06.04h.03s0-.02,0-.02c-.02-.03-.03-.04-.05-.04-.02-.03-.03-.03-.03,0-.02,0-.03,0-.04.02,0,.02-.02.04-.04.06.02,0,.03.02.03.04l.04-.06ZM208.53,52.59l.29-.27v-.03s-.03,0-.03,0c-.02.02-.07.04-.15.07l-.04.06-.06.15s0,.02-.01.06v-.03ZM212.63,47.42s.06,0,.07-.02c.02-.02.04-.06.06-.12l-.15.07.02.07ZM212.87,47.21c.08-.05.12-.09.13-.14.02-.02.03-.03,0-.03h-.03s-.13.13-.13.13l-.04.06.07-.02ZM213.27,46.74s.06-.02.1-.01c.05-.01.07-.04.08-.08l-.02-.07h-.03c-.1.06-.15.09-.15.09l.02.07ZM213.53,46.57s.04-.03.04-.06c0-.04.03-.07.05-.09v-.03s-.03,0-.03.02c-.05.03-.08.06-.08.08l.02.07ZM214.04,47.07s0,.01,0,.03c0,0,.01,0,.04-.02,0-.02,0-.03,0-.03.02-.02.04-.03.04-.06l-.03-.04-.05.09v.03ZM214.68,46.39c.07,0,.12-.04.15-.1.03-.02.03-.03,0-.03,0-.02,0-.03,0-.03h-.03c-.06.07-.09.1-.09.1-.02,0-.03,0-.04.02.02,0,.03,0,.03,0l-.04.02ZM214.63,45.43s.03-.07.05-.09v-.06s-.05,0-.06.02l-.05.09s0,.08.01.1l.04-.06ZM215.75,61.72l-.04-.14c-.02-.09-.03-.17-.01-.23.04-.38.08-.66.11-.83h.03s.08-.53.08-.53l.14-.33c.04-.17.07-.28.11-.34.08-.16.12-.27.14-.33v-.06s-.02,0-.02,0c0,.02,0,.03,0,.03-.03.02-.04.05-.05.09-.03.04-.1.14-.2.32v.03s-.04.1-.14.17l-.12.27v.03s-.03-.04-.03-.04l.06-.12s0-.06-.02-.07l-.02-.07-.04.06-.06.12s0,.07.05.08v.03s-.12.69-.12.69l-.04.02v-.03s.03-.55.03-.55l.04-.32c.05-.23.13-.42.25-.57l.04-.06s.02-.03.04-.02v.06s-.05.09-.12.21l.02.07.02.04.05.08s.01-.06.01-.06v-.03c.02-.06.04-.12.08-.18.05-.05.08-.1.06-.15.05-.01.08-.05.09-.11.03-.06.06-.11.07-.15.05-.05.11-.14.15-.26.06-.1.11-.17.15-.23.12-.24.22-.4.3-.49l.18-.22c.13-.19.2-.33.22-.41l.02-.09c.02-.08.05-.17.09-.27.06-.1.1-.16.11-.21,0-.04.02-.06.04-.06.03-.04.07-.08.13-.14.06-.05.11-.12.17-.19.05-.05.09-.11.1-.17.03-.06.07-.12.1-.17v-.03s-.05.04-.06.02c0-.02,0-.03-.03-.04-.05.03-.08.06-.08.08-.03.04-.06.07-.09.11,0,.04-.03.08-.06.12-.08.05-.12.13-.12.24,0,.04-.03.06-.08.05l-.03-.04v-.06c.05-.06.09-.13.12-.21.04-.1.09-.18.15-.23.18-.22.32-.41.42-.56.07-.12.13-.22.2-.32.09-.09.16-.18.22-.28l.04-.06v-.03s-.02,0-.02,0c-.07.03-.14.1-.21.22-.03.04-.07.07-.12.1-.02.02-.05.03-.08.05-.07.12-.11.21-.12.27l-.08.08s0,.03.02.04v.03s-.25.21-.25.21c-.06.05-.12.13-.21.22-.07.1-.11.17-.15.23l-.43.63-.25.4-.05.09-.28.4s-.01.02-.03,0c-.02,0-.03-.02-.02-.04l.03-.16h.03c.03.06.06.05.07-.01.01-.06.03-.1.06-.12.02-.08.07-.2.14-.36v-.03c.02-.06.08-.15.19-.25l.08-.08s.02-.04.04-.06c.03-.04.06-.05.08-.05s.04-.01.04-.06v-.03c.02-.08.09-.18.2-.29.12-.24.26-.47.44-.69.09-.11.14-.18.14-.2l.17-.32c.03-.06.07-.13.11-.21.04-.1.09-.17.14-.2.03-.06.06-.12.07-.18.04-.08.08-.13.13-.17v-.06s-.05,0-.06.02c-.02,0-.03,0-.04.02-.02.1-.07.19-.15.26-.08.07-.14.12-.17.16l-.1.14c-.02.08-.06.12-.12.1-.06-.01-.1.02-.12.1,0,.02-.02.04-.04.06-.02.02-.05.02-.07.02l-.08.08c-.39.61-.72,1.08-.99,1.39l-.31.39s-.02.03-.04.02l-.02-.04s0-.08-.01-.1c.07-.12.13-.2.19-.25.14-.25.23-.42.27-.5v-.03s-.03.02-.03.02l-.18.22c-.13.08-.24.19-.33.32,0,0,0,0-.03,0,0,0,0,.01,0,.03v-.03s-.01-.07-.01-.07v.06c-.1.09-.21.23-.33.42l-.07.02s.02,0,0-.03c0,0,.01,0,.03,0,.07-.12.11-.21.12-.27.06-.05.12-.16.2-.32v-.03c.08-.05.14-.12.19-.22.07-.12.12-.19.15-.23v-.06s.03-.06.03-.06l-.07.02c-.04.1-.14.22-.28.37-.03.04-.06.07-.09.11-.02.02-.05.04-.08.08-.05.03-.08.05-.08.05l.02-.09.18-.22c.03-.06.07-.12.1-.17.04-.08.08-.15.11-.21l.13-.17c.05-.03.06-.06.02-.09-.02,0-.03,0-.03,0,0-.02,0-.03,0-.03l.18-.22v-.03s-.02,0-.02,0l-.08.08-.04.02v-.06s.11-.13.21-.29l.68-.9.53-.8c.06-.05.1-.13.15-.23.07-.12.12-.2.15-.26.18-.22.31-.4.38-.54.06-.1.14-.2.23-.31.11-.13.19-.24.24-.34.3-.37.51-.65.64-.84.21-.26.38-.51.52-.74.05-.12.12-.24.21-.35.12-.13.19-.22.22-.28l.67-.97.4-.5s.06-.07.09-.11c.03-.06.06-.12.07-.18.3-.37.49-.66.58-.86l.19-.25c.03-.06.08-.12.14-.2.06-.1.12-.19.16-.29l.56-.76c.07-.12.25-.33.53-.64.11-.19.17-.3.2-.32.06-.05.04-.09-.04-.11l-.25-.05c-.43-.05-.76-.08-1-.08-.34-.03-.62-.05-.84-.05-.32-.05-.72-.05-1.21,0-.26,0-.5.03-.7.08-.2.02-.37.04-.5.06l-1.11.12s-.05.03-.08.05c-.17-.04-.34-.03-.53.02-.16.05-.29.09-.38.11-.19.09-.34.15-.43.17-.05.03-.08.05-.08.05-.03.02-.06.02-.1.01.02,0,.04-.01.04-.06l.34-.19.5-.22s.06-.03.11-.04c.05-.01.07-.03.08-.05l.26-.14.04-.02.61-.23.14-.04s.06,0,.11-.04c.02,0,.03,0,.03,0,0-.02,0-.03,0-.03h.06s.09.02.13,0c.05-.03.1-.06.15-.07v-.03s-.02,0-.02,0l-.29-.03-.06-.04v-.06s.45-.2.45-.2l.04-.06.28-.07v-.03s-.02,0-.02,0h-.06s0,0,0,.02c0,0,0,0-.03,0l-.11.04s-.01,0-.03,0c0,0,0-.01,0-.03-.04,0-.06-.01-.06-.01l-.37.02s-.1.01-.16,0h-.03s.04-.06.04-.06h.13s.11-.08.11-.08l.04-.02c.11-.02.29-.07.52-.15h.03c.08.02.15.03.2.02.05-.03.18-.05.4-.04h.1s.06-.06.08-.06c.06.01.13.02.19,0,.07-.03.15-.03.23-.02h.03s.06.02.06.02c.03-.02.05-.02.07-.02.04,0,.08,0,.1-.01.02,0,.07-.02.15-.07.05-.03.08-.04.1-.01,0,.02,0,.03,0,.03.02,0,.03,0,.04-.02l.11-.07s0-.03-.02-.04l-.26-.02h-.82s-.08,0-.17.02h-.03s.04-.03.04-.03l.17-.03.04-.06s-.05.02-.07.02l-.09-.02s-.04-.04-.09-.05l-.53.02h-.03s.04-.03.04-.03l.4-.04h.36s.04-.01.04-.01h-.03s-.04-.02-.06-.02c0-.02,0-.02-.03,0-.06-.01-.12-.01-.16,0h-.06s.07-.03.07-.03c.23-.04.39-.06.5-.06l.07-.02h-.06c-.1-.04-.19-.04-.26-.04-.07,0-.14,0-.22-.02-.08-.02-.15-.02-.2,0-.07,0-.16,0-.29-.03v-.03s.43,0,.43,0c.03-.02.05-.02.07-.02.04,0,.08,0,.1-.01.16-.05.38-.08.64-.09.4-.02.64-.04.73-.04.02,0,.03,0,.04-.02h-.06c-.07,0-.17,0-.3.02-.11,0-.21-.02-.31-.07-.02-.03-.04-.03-.06-.01,0,0-.01,0-.03,0l.11-.04.14-.04c.18-.05.38-.06.6-.03.22,0,.36,0,.43,0h.4s.1-.02.1-.02c.09-.02.17-.03.23-.02.26,0,.42-.02.46-.03h.16s.16.04.16.04h.06s.1,0,.1,0l-.09-.05-.39-.15-.04.02.04-.02.41.09.19.04.04-.02s.08-.05.14-.04c.11-.02.28-.03.5-.02l.54.05c.22-.02.55-.02.99-.02.13-.01.37,0,.71.02.11-.02.25-.02.43,0,.17,0,.31,0,.39-.01.37,0,.7,0,.97.05.13,0,.25.01.36.01.13-.01.27-.02.4-.01.1.02.22.04.35.04.13-.01.26,0,.39.02l.4.12c.08.04.17.06.28.06l.17.1.14.1h.06c.07.09.17.16.29.21.12.05.2.08.24.09.04,0,.15.06.32.17.17.1.3.23.38.38.04.12.17.32.39.61.07.06.14.13.18.2.05.08.1.14.15.2,0,.02,0,.06.04.11.05.08.07.16.05.24l-.03.13c-.01.06-.05.08-.11.04-.02-.03-.05-.01-.11.04-.05.03-.08.07-.09.11,0,.04-.03.08-.06.12,0,.04,0,.09,0,.13.04.14.05.24.03.3-.02.08-.02.15,0,.19,0,.02,0,.13.03.33-.01.06-.07.08-.18.06l-.4-.28c-.06-.01-.12-.01-.16,0-.06-.01-.09-.03-.09-.05-.21-.24-.4-.4-.58-.49-.07-.06-.23-.11-.45-.16-.23-.07-.49-.11-.8-.11-.3-.02-.52-.04-.65-.04h-1.08s-.59,0-.59,0l-.09-.02.05.08.05.21c.03.05.05.08.05.08.11.18.11.34,0,.49l.02.04c0,.07-.01.12-.07.15-.05.01-.08.03-.11.04,0,.02-.02.03-.04.02s-.03,0-.03,0l-.19-.17-.09-.02s-.04.01-.04.06c-.05.05-.16.09-.32.1-.02,0-.07.02-.14.07-.03.04-.16.18-.39.44-.18.14-.38.35-.6.66l-.7.96-.66.81-.54.67c-.13.21-.26.4-.38.57-.12.15-.23.29-.32.42-.29.35-.46.57-.5.65-.03.04-.06.08-.1.14-.03.06-.07.12-.1.17l-.26.3c-.12.17-.2.28-.24.34l-.28.4-.42.56-.52.61c-.12.17-.24.32-.36.45-.09.13-.19.25-.27.37l-.7.8c-.17.27-.34.49-.51.68-.25.34-.42.6-.53.77-.03.06-.07.14-.12.24-.04.08-.1.17-.19.29-.06.1-.14.2-.23.31-.09.13-.19.26-.28.4l-.9,1.12-.26.47-.34.52c-.24.41-.38.7-.42.89l-.24.96-.05.51s-.02.03-.04.02v-.03s0-.01.01-.03c0,0-.01,0-.04.02v-.03s-.03,0-.03.02l-.04.06-.02-.07ZM216.25,58.16c.12-.15.2-.26.24-.34l.07-.02c-.05.05-.15.18-.27.37l-.04.06v-.06ZM216.56,57.8c.01-.06.01-.11,0-.13l.04-.06.02.07-.06.12ZM218.05,55.73l.12-.1-.02-.07s-.02.03-.04.02l-.1.14v.03s.03-.02.03-.02ZM217.91,43.52s.07,0,.08-.05c.06.01.11.01.13,0h.03s.26-.13.26-.13c.08-.05.19-.06.33-.03l.06.04h-.06s-.18.05-.18.05c-.04.06-.08.08-.15.07-.04,0-.1.01-.18.06l-.23.02s-.05.02-.07.02c0-.02,0-.03-.03-.04ZM219.36,43.15c.05-.03.09-.05.11-.04l-.02-.04-.11.04.03.04ZM219.87,42.18h.03s.26,0,.26,0h.03s-.04.03-.04.03c-.07,0-.15,0-.26-.02h-.03ZM228.08,64.64c-.02-.09-.02-.16,0-.19.1-.24.17-.4.23-.47.05-.12.1-.23.17-.32.06-.07.11-.14.14-.2l.12-.24c.04-.06.07-.12.1-.17.04-.06.07-.13.11-.21l.07-.15s0-.01,0-.03c.02,0,.02,0,0-.03-.05-.06-.04-.14.05-.25l.26-.44c.08-.16.15-.27.21-.35v-.03s-.09-.02-.09-.02l.22-.28.02.07.13-.14-.14.04.14-.2v-.06s.02-.05.03-.09c.03-.04.07-.06.11-.07.03-.02.05-.07.07-.15v-.06c.06-.01.09-.04.1-.08.03-.04.06-.06.08-.08l.29-.43.06-.12s-.01-.04-.06-.04l.19-.25.05.08v-.03s.02-.06.02-.06c.02-.1.07-.19.15-.26l.3-.46c.09-.11.15-.22.17-.32.04,0,.05-.01.01-.06-.03.04-.07.08-.13.14-.03.06-.07.09-.12.1l.3-.46h-.03s-.13.13-.13.13l-.25.24-.04.06c-.08.05-.14.11-.2.19-.06.07-.1.13-.13.17,0,.02-.03.03-.07.02v-.06s.05-.16.05-.16l.04-.06c.05-.03.14-.15.28-.37v-.06c-.02-.05,0-.12.09-.21l.06-.12c-.05.03-.11.09-.17.16-.05.03-.11.09-.17.16h-.03c.36-.56.76-1.13,1.19-1.71-.07,0-.12.04-.15.1-.03.06-.07.11-.1.14,0,0-.1.07-.3.2h-.03s.09-.12.09-.12c.06-.1.11-.14.13-.14,0-.02.03-.05.08-.08.02-.02.04-.05.05-.09,0-.09.04-.13.13-.14l.05-.09s-.02-.05-.02-.07c.02-.02.04-.03.04-.06l.18-.22h-.03c-.19.17-.38.4-.58.69-.03-.07-.02-.11.03-.13.05-.03.08-.05.08-.05l-.1-.15-.06.15s-.01.05-.02.09c0,.02-.03.04-.08.05-.02,0-.03,0-.04.02,0,.02-.02.04-.04.06,0,.02-.02.03-.04.02h-.03s.07-.19.07-.19l.33-.48c.03-.06.07-.1.09-.11.03-.04.06-.06.08-.08.06-.07.09-.13.1-.17,0,0,0-.02.01-.06l-.15.07c.03.07,0,.1-.11.07v.13s-.04-.11-.04-.11c-.21.17-.32.27-.32.29-.01-.05-.01-.09,0-.13.03-.04.07-.08.13-.14.09-.11.14-.19.15-.23,0-.04.03-.07.05-.09.03-.04.06-.06.08-.08.06-.1.15-.2.26-.3.1.02.15-.02.13-.14l-.04.02.09-.11.02.07.06-.12c0-.09.03-.13.09-.11.02-.08.04-.14.07-.18l.45-.59.13-.17s0-.03-.02-.04l-.22.28-.26.3-.26.3-.26.3s-.07.06-.11.07c-.05.01-.08.03-.11.04h-.03c.41-.51.76-.96,1.04-1.35h-.06s-.46-.01-.46-.01c-.08-.02-.21-.02-.39-.02h-1.24s-.46.02-.46.02h-.16c-.07,0-.17.02-.3.03-.11,0-.2.01-.27.04-.02,0-.07.04-.16.13l-.31.39c-.06.07-.21.28-.46.62l-.63.81c-.09.11-.18.21-.26.3-.06.07-.12.15-.18.22l-.53.77-.11.21c-.13.19-.24.33-.32.42l-.14.2-.59.89-.12.24-.33.48c-.07.12-.15.23-.24.34-.07.14-.16.29-.26.47-.08.16-.15.27-.21.35,0,.02-.02.04-.04.06-.03.04-.06.06-.08.08,0-.07-.02-.12-.03-.17-.01-.05-.02-.09-.03-.14l.06-.12.15-.56s0-.09-.04-.14c-.01-.05-.02-.1-.03-.17,0-.02,0-.03-.02-.04-.02.02-.04.04-.04.06l-.08.08c-.05-.06-.09-.11-.1-.15-.02-.03,0-.06.06-.12.06-.16.15-.33.27-.5l.35-.58.3-.46-.02-.07c-.09.11-.2.25-.32.42-.1.17-.2.31-.28.4h-.03c.04-.11.1-.22.17-.36.07-.12.14-.24.21-.38h-.03s-.25.4-.25.4l-.07-.11.34-.65c-.18.14-.4.37-.64.71h-.03s.05-.1.07-.19l.21-.35v-.03c.05-.01.09-.04.12-.07.01-.06.04-.11.07-.15l.09-.11c.11-.19.18-.32.21-.38l.03-.13c.07-.12.11-.21.12-.27l.05-.09-.07.02c-.07-.06-.14-.06-.19,0-.03.06-.06.1-.09.11-.15.21-.3.38-.44.53-.03.04-.1.09-.2.15l.26-.44s-.04,0-.07.02c-.02,0-.04-.03-.05-.08l-.27.2c.19-.26.32-.47.39-.6v-.03c-.07.03-.13.08-.19.15-.06.07-.12.14-.17.19.22-.39.43-.73.64-1.01v-.03s-.07.05-.07.05l-.4.5-.22.28-.04.06-.02-.07c.02-.08.04-.13.07-.15l.28-.37.12-.27c.18-.22.31-.4.38-.54-.08.09-.16.19-.23.31-.08.09-.17.18-.25.27.04-.08.12-.19.24-.34-.14.12-.22.22-.26.3h-.03c.06-.08.21-.29.46-.63.18-.31.33-.54.47-.68l.12-.24c.09-.13.2-.26.31-.39.12-.15.23-.29.32-.42l.34-.52c.06-.07.13-.18.2-.32.09-.13.21-.28.36-.45l.42-.56c.1-.17.28-.43.53-.77l.36-.45.34-.52c.21-.35.37-.61.5-.78l.39-.6c.04-.08.12-.19.24-.34.14-.23.21-.35.21-.35.07-.12.19-.29.37-.51l.15-.23c.09-.13.21-.34.36-.61.27-.46.47-.81.59-1.05.11-.19.25-.38.42-.56.08-.07.2-.11.35-.12.02,0,.06,0,.11-.04.18,0,.29,0,.36.01l.48.07c.13-.01.23,0,.29.03.18.08.3.16.37.24l.08.08.24.09s.07.04.09.02c.05-.01.08,0,.09.02.04.03.07.07.1.12.06.14.14.27.25.38.18.19.27.31.28.36l.04.11c0,.09.03.22.08.41v.06c.04.06.04.1,0,.13v.13c.03.07.02.1-.05.09-.13.01-.23.07-.3.16-.06.07-.09.12-.1.14l-.47.65c-.07.12-.14.23-.21.35-.06.1-.13.2-.2.32-.28.46-.53.77-.75.92l-.14.2-.31.39c-.03.06-.08.12-.14.2-.06.07-.12.16-.19.25v.06s.14.03.14.03c.18,0,.31,0,.39.02l.09.02.31.1.67.08c.13,0,.28.02.45.03.17.02.37.05.6.1.08.02.14,0,.18-.06.13-.19.34-.45.63-.78l.69-.93.49-.61.45-.56c.08-.07.14-.14.18-.22.06-.1.12-.17.18-.22.06-.07.12-.16.19-.25.06-.1.14-.2.23-.31l.4-.5c.25-.34.44-.59.59-.76l.69-.77c.12-.15.27-.28.45-.39.27-.14.49-.21.67-.22l.22.05.6.1s.08.04.11.09c.04.03.07.06.11.09.06.01.11.05.14.1l.13.16.24.12h.13s.13.08.28.22l.11.12c.08.04.12.09.13.16.02.09.05.18.07.28.03.07.05.13.06.18l.16.49s-.04.03-.04.06c.02.03.02.05.02.07-.02.1,0,.21.06.31.05.08.03.14-.07.18l-.04.06c-.03.06-.09.06-.16,0-.12-.03-.22-.04-.29-.03-.04,0-.09,0-.14.04-.05.03-.1.04-.14.04-.02,0-.06,0-.11.04l-.41.37-.34.35c-.11.09-.22.2-.34.35-.09.13-.18.24-.27.33l-.95,1.04-.38.54c-.06.05-.13.13-.21.22-.06.07-.12.16-.19.25l-.7.83s-.03.04-.01.06c.02.03.04.03.06.01l.09.02.4.12s.08.05.12.06c.05-.01.09,0,.12.03-.02,0-.05,0-.1.01-.02,0-.05-.02-.09-.05-.08-.02-.16-.02-.23-.02-.07,0-.12.02-.17.03-.13.01-.23.04-.28.07,0,0-.06.04-.19.12.08.13.18.2.28.22.09,0,.17.02.25.05.1.02.2.03.29.03.04,0,.1,0,.16,0,.07,0,.12,0,.16,0,.11-.02.21.01.28.09.12-.04.19-.05.23-.02l.07-.02s.07.03.09.05c-.02,0-.03,0-.04.02,0,.02-.02.03-.04.02h-.03s-.1-.02-.16,0c-.05.01-.09,0-.12-.03h-.03c-.07.02-.25.06-.55.1l-.42.11s0,.01,0,.03c0,0,0,0,.03,0l.23.02.12.06.09.02c.15.03.27.03.36-.02v-.03c-.14-.03-.26-.05-.34-.04v-.03s.2,0,.2,0c.05-.01.1-.01.16,0,.06.01.11.01.13,0h.2s.05.09.05.09c.04,0,.06.03.05.08,0,.02-.02.03-.04.02-.02,0-.04,0-.07.02-.18,0-.3.02-.37.05l-.25.11s0,.03,0,.03c.02,0,.03,0,.03,0l.83.11c.39,0,.69-.01.89-.04h.06c.27.07.48.14.61.21h.16c-.1.07-.16.1-.18.09-.55.01-1.11.04-1.69.09-.37,0-.94.04-1.69.09l-1.26.09h-.03c-.13,0-.24.03-.31.06-.05.01-.1.05-.16.13-.06.05-.11.12-.17.19-.13.1-.33.33-.61.69-.05.03-.09.08-.13.14-.03.04-.06.07-.09.11l-.51.71s-.04.05-.05.09c0,0-.08.08-.25.24-.07.12-.13.2-.19.25l-.49.61-.4.5c-.05.03-.17.16-.35.38l-.09.11c-.05.03-.17.15-.37.35l-.45.56-.22.28-.29.43s-.04.06-.12.1c-.06.07-.12.16-.19.25-.05.12-.13.24-.24.37-.11.19-.24.37-.41.53l-.14.2-.96,1.27-.68,1.03-.65.88-.29.43s-.03.07-.05.09ZM225.77,55.79c-.09.02-.15.03-.17.03l-.04.19h.03s.18-.22.18-.22ZM226.08,55.4c-.08-.04-.13-.03-.14.04l.14-.04ZM226.18,55.26l.02-.09h-.03s-.04,0-.05.05v.1s.06-.06.06-.06ZM225.73,54.15h-.03s-.06.11-.06.11l.02.04.06-.15ZM226.44,54.93l.02-.09c.01-.06.05-.09.11-.07.03-.02.03-.03,0-.03,0-.02,0-.03-.02-.04h-.03s-.2.18-.2.18c0,.02,0,.06.04.11l.08-.05ZM226.74,54.47c.02-.08.04-.13.07-.15h-.06s-.03.09-.06.1l.06.04ZM229.77,60.16c.03-.15.13-.31.3-.49v.06c-.03.08-.08.16-.16.23-.06.1-.12.18-.15.26v-.06ZM226.94,54.15v-.06s-.02,0-.02,0l-.08.08h.1ZM230.03,60.45s.03-.09.14-.2c.02-.02.04-.05.05-.09,0-.02.02-.04.04-.06v-.03c.11-.07.17-.12.2-.15h.03s-.47.53-.47.53ZM227.39,52.08v.03s-.07.02-.11.01v.1s.11-.14.11-.14ZM230.85,59.09l.08-.24h.03s-.09.28-.09.28l-.02-.04ZM227.51,52.24c.1-.07.12-.15.05-.25-.09.11-.11.19-.05.25ZM228,51.2v-.03c-.1.07-.21.18-.33.35-.1.17-.15.28-.14.33l.47-.65ZM228.13,51.95l-.12-.03-.03.13.02.04.13-.14ZM227.78,51.94c.07-.12.19-.29.37-.51l-.21.05.09.02-.28.4.02.04ZM230.74,57.33c.23-.28.38-.44.43-.5,0,.02,0,.03,0,.03.02,0,.03,0,.03,0-.05.01-.07.03-.08.05,0,.02-.02.04-.04.06l-.08.08c-.07.12-.15.21-.26.27ZM228.12,51.88l.11-.07.08-.05c-.02-.09.01-.15.1-.17v-.03s.16-.26.16-.26c-.07,0-.1.02-.11.04-.06.05-.16.2-.33.45-.03.02-.04.03-.05.06.02,0,.02.01,0,.03h.03ZM228.05,51.15c.09-.11.14-.18.14-.2h-.03s-.13.16-.13.16l.02.04ZM231.18,57.09s-.03,0-.03,0c0-.02,0-.03,0-.03l.29-.3v.16c-.06-.03-.1-.03-.13,0-.03.04-.06.06-.08.08l-.05.09ZM228.27,51.19c.09-.02.15-.11.19-.25,0,.02-.03.05-.08.08-.05.03-.08.06-.08.08,0-.04.04-.1.1-.17h-.03s-.03.04-.08.07c-.03.02-.02.05.01.1l-.02.09ZM228.28,50.84c.07-.12.14-.2.22-.25h-.03c-.08.04-.15.11-.21.21l.02.04ZM228.56,51.19c.06.03.09.02.11-.04.01-.06.03-.1.06-.12l.17-.16c.06-.07.08-.13.07-.18-.11.11-.2.21-.26.3-.06.07-.11.14-.14.2ZM231.54,56.48s.08,0,.1-.01c.03-.04.05-.07.05-.09.03-.02.04-.04.04-.06,0-.04.03-.07.05-.09-.06-.01-.1,0-.1.01-.05.03-.08.06-.08.08-.02.02-.04.05-.05.09.02.03.01.05-.01.06ZM229.35,51h.03s0,.08.01.11l.04-.06.06.04s.05-.12.12-.24h-.03c-.06-.02-.12-.01-.17.02-.03.04-.06.06-.08.08-.03.04-.05.09-.07.15v.16s.03,0,.03,0l.06-.28ZM229.12,50.59s.07,0,.07-.02c.06-.05.11-.13.15-.23.05-.12.09-.21.12-.27h-.03s-.08.1-.14.19c-.06.07-.1.15-.12.24l-.07.02s0,.06.02.07ZM232.32,55.9c.06-.07.09-.12.1-.14h-.03s-.09.1-.09.1l.02.04ZM232.08,55.52c.09-.13.21-.26.35-.38v-.06s-.02,0-.02,0l-.22.25s-.04.05-.05.09c0,.02-.02.04-.04.06l-.16.13v.06s.15-.13.15-.13ZM231.84,56.19c.27-.36.45-.61.53-.77l.02.07s.03-.08.06-.12c.03-.04.04-.08.03-.13l.07-.02c.03.05.05.07.06.04.03-.04.05-.07.05-.09,0-.02,0-.03-.02-.04,0-.02.02-.04.04-.06l.13-.17c.17-.16.26-.25.29-.27l-.09-.02.16-.13c-.03-.05-.06-.08-.08-.08-.01.06-.03.1-.06.12-.07,0-.11.07-.14.2-.05.03-.08.06-.08.08,0,.02-.02.06-.06.12,0,.04-.05.07-.11.07-.02,0-.03,0-.04.02l-.06.12c-.04.06-.07.11-.1.14-.02.02-.05.03-.08.05l-.05.06-.19.29s-.04.02-.04.02c.02,0,.03,0,.03,0-.05.01-.1.04-.15.1-.03.04-.05.09-.07.15l.07-.02s-.08.07-.15.1c-.05.01-.07.04-.08.08l.12.06ZM233.15,54.48c.05-.03.08-.05.08-.05.05-.03.06-.07.03-.13l.08-.05.05-.09h-.03s-.15.09-.15.09c-.02.02-.04.06-.06.12.01.05.01.08.01.1ZM233.34,54.09c.08.04.13.02.15-.07l.14-.2-.15.1s.02.06.01.1c-.08-.02-.13,0-.15.07ZM239.76,52.69s.07.03.09.05v-.03s-.04-.08-.04-.08l-.04.06ZM238.65,64.24c-.08-.04-.12-.14-.13-.29l-.02-.2s0-.01,0-.03c0,0,0,0-.03,0-.03.02-.03,0-.02-.04.01-.06.01-.11,0-.13v-.06s-.03.06-.03.06l-.08.05s-.05-.03-.08-.08c0,0,0-.02.01-.06,0-.02-.02-.03-.06-.01l-.02-.07.07-.34v-.06c.03-.08-.02-.16-.13-.23l-.02-.07c.05-.25.1-.43.15-.53,0-.04.05-.12.12-.24l.06-.12s0-.01,0-.03c0,0-.01,0-.03,0h-.03s-.07.17-.07.17l-.04.06-.02-.07.13-.3v-.03c.06-.05.06-.1,0-.13-.02-.03-.02-.06-.01-.1,0-.04.03-.08.06-.12,0-.02.01-.05.02-.09.03-.02.06-.02.1-.01v-.03s-.01-.07,0-.13l.09-.24.14-.2s.05-.12.12-.24v-.03c-.06-.08-.04-.13.07-.15,0-.02.02-.03.04-.02l.05-.09-.08.05h-.03s0-.04,0-.04c.01-.06.05-.11.1-.14.03-.02.03-.04.01-.06-.01-.05-.02-.08-.01-.1h-.03s-.13.16-.13.16l-.22.28-.04.02v-.03s.02-.06.02-.06c0,.02-.02.03-.04.02l-.45.59-.18.22-.2.32-.04.06v-.06c.07-.14.17-.35.31-.62l.03-.13.05-.09.1-.31s.04-.07.1-.14v-.06s-.06.02-.06.02c-.04.08-.17.27-.38.57l-.24.34c-.03.06-.08.09-.15.1v-.03s.21-.35.21-.35l.18-.36s.04-.09.11-.21v-.06s-.06.02-.06.02c-.12.17-.2.27-.23.31-.02,0-.03,0-.04.02v-.03s0-.13,0-.13v-.06s.1-.11.1-.11v-.06s-.02,0-.03.02c-.03.04-.09.13-.19.29-.01.06-.06.12-.13.17v-.03c.08-.12.11-.22.11-.31,0-.04.03-.07.05-.09.06-.07.13-.21.22-.41.07-.12.13-.24.18-.39.07-.14.14-.26.21-.38l.14-.36.31-.52.46-.75s.13-.2.38-.54l.21-.38.28-.37.26-.44.26-.47.35-.58.3-.49.28-.4c.04-.08.18-.32.42-.73l.32-.55c.16-.23.32-.48.49-.75.05-.14.2-.43.45-.85l.46-.75.03-.16.17-.32c.03-.06.08-.12.14-.2.06-.1.12-.19.16-.29.02-.02.04-.06.06-.12l.21-.38.23-.31c.09-.2.16-.35.23-.44l.46-.62c.07-.14.21-.29.4-.47l.29-.3c.05-.03.1-.04.14-.04.06.01.12.01.16,0,.07,0,.14,0,.23.02l.3.13h.03c.07,0,.14.03.21.09,0,.02.01.04.06.04.09,0,.24.02.44.06.06.03.12.06.18.07.07,0,.12,0,.16.03l.42.19s.07.05.15.07c.05.06.12.11.19.17.07.06.13.11.16.17.19.24.29.43.3.59.02.09.05.15.09.18l.02.04-.09.44-.1.47-.1.47v.06s-.24.61-.24.61l-.15.69-.09.27-.1.47c-.05.23-.08.41-.08.54l-.11.37-.07.61v.59c.04.12.06.24.05.37.02.11.04.22.06.31-.01.06,0,.08.06.04.02,0,.06,0,.11-.04.05-.03.09-.02.12.03,0,.02,0,.03.02.04.02,0,.04,0,.07-.02l.2-.15.27-.17.44-.39c.06-.1.18-.21.34-.35.05-.03.23-.2.53-.51l.61-.69c.05-.05.11-.12.17-.19.08-.07.16-.14.24-.21.03-.04.06-.06.08-.08.05-.03.1-.07.15-.1l.19-.25s.01,0,.04-.02c.03-.04.05-.04.07-.02h.03s.08-.05.15-.06c.07,0,.11-.02.14-.04.13-.08.21-.15.24-.21l.35-.38c.06-.1.13-.16.2-.19l.11-.07.51-.68.08-.08-.06.12-.02.09s.03-.07.05-.09c.17-.16.25-.24.25-.24.19-.26.34-.46.45-.59l.38-.38.08-.08c.1-.07.19-.1.25-.11l.07-.02.08-.05-.02.09c.08-.07.15-.08.2-.02l.14.1.09.02c.08.02.2,0,.34-.06.19-.07.32-.11.38-.11h.06s.03.18.03.18c-.02.1-.02.18.02.23.02.09.05.16.08.21l.02.04c.12.03.2.09.22.18,0,.02,0,.03.02.04.04,0,.07.03.09.05.03.05.05.09.04.11-.01.06.03.11.14.13.04,0,.06.02.06.04,0,0,.02.05.07.15.04.03.05.07.04.11.01.05,0,.08-.02.09-.03.02-.03.05-.02.09.02.03.02.07,0,.13.02.11.07.19.15.23,0,0,.02.03.05.08l-.07.02s-.07.06-.05.09c.02,0,.03.02.02.04h-.06c0-.06-.01-.06-.06-.03-.29.13-.49.3-.6.49l-.53.93s-.06.13-.17.32c-.06.07-.11.15-.15.23-.04.06-.07.12-.1.17-.04.1-.12.22-.24.37-.05.03-.08.05-.08.05-.05.14-.11.26-.17.36-.06.1-.11.18-.15.26-.08.07-.19.22-.33.45l-.22.25-.06.12c-.12.17-.23.32-.33.45-.09.13-.17.26-.24.37-.09.11-.2.28-.34.52l-.26.3-.71.99-.57.83-.53.77-.39.57c-.1.07-.19.17-.26.3-.05.14-.09.23-.12.27-.04.08-.09.17-.15.26-.06.07-.11.14-.14.2-.14.23-.25.4-.34.52,0,.02-.09.15-.24.37-.03.04-.1.14-.2.32-.06.07-.14.23-.23.47-.11.22-.23.41-.35.58-.05.12-.14.28-.26.47-.12.17-.21.33-.26.47-.14.23-.23.42-.29.56l-.17.36c-.03.06-.1.12-.2.19-.08.05-.12.1-.13.17-.05.12-.1.31-.15.56,0,.02,0,.04-.01.06.01.05,0,.09-.03.13-.01.06-.05.13-.11.21,0,.02-.02.03-.04.02-.02,0-.03,0-.04.02-.03.02-.04.03-.04.06.02.03.02.05.02.07v.03s-.03-.04-.03-.04h-.06s-.04.01-.04.01c0,.04-.03.07-.05.09l.02-.09c-.07-.1-.1-.15-.1-.15v-.16s.07-.48.07-.48c.03-.06.07-.18.11-.37l.22-.57c.05-.14.1-.27.15-.39.07-.12.12-.22.17-.32.06-.07.14-.24.24-.5l.32-.72s.04-.03.04-.06c0-.04.03-.07.05-.09l.15-.39.11-.21s0,0-.03,0c0,0,0-.01,0-.03l-.04.02c-.14.12-.25.28-.33.48l-.14.2c-.21.26-.38.58-.5.97-.03.06-.07.13-.11.21-.04.1-.08.21-.11.34l-.1.44-.04.19h-.03s.02-.1.02-.1l-.06-.04v.03s-.02.06-.02.06c-.02,0-.06.04-.13.14v.03s0-.03,0-.03l.08-.38.07-.34c.01-.06.04-.11.07-.15v-.03c-.03-.05-.04-.09-.04-.11,0-.02.01-.05.02-.09.03-.04.03-.08,0-.13-.04,0-.03-.05.03-.13l.21-.51s.04-.08.09-.11l.12-.24-.02-.04s-.07,0-.06-.01c.02-.02.04-.02.04-.02l.19-.42s0-.08-.04-.11c-.02-.03-.02-.04-.02-.04-.03-.05-.08-.04-.14.04-.05.14-.14.28-.25.4,0,.02-.03.06-.09.11-.03.06-.06.12-.07.18l-.03-.17-.09.11c-.12.15-.22.32-.31.52v.03s0-.03,0-.03v-.19s.12-.37.12-.37l.02-.09c.03-.15.06-.25.1-.31l-.02-.07v.03c-.07.07-.13.19-.21.35-.06.07-.13.19-.21.35,0,.02-.02.03-.04.02v-.03s.14-.33.14-.33v-.06s.06-.06.06-.06l-.09-.02h-.03s0-.04,0-.04l.38-.67s.05-.09.07-.15c0-.02.04-.07.1-.14l-.02-.07-.04.06c-.11.13-.32.44-.63.94l-.05.09.03-.13.17-.32v-.03s-.03,0-.03.02l-.08.08h-.03s0-.04,0-.04l.16-.29c.08-.16.15-.27.21-.35l.17-.32c.04-.08.06-.18.07-.31-.02-.03-.01-.05.01-.06.22-.43.34-.69.36-.77l.15-.39.41-.67c.1-.17.2-.34.3-.49.12-.15.23-.31.33-.48.03-.04.04-.06.01-.06,0-.02-.01-.04-.06-.04l-.26-.02c-.06-.01-.17-.06-.33-.14-.13-.03-.21-.07-.27-.12-.02-.03-.04-.03-.06-.01-.02,0-.04,0-.06-.01h-.1s-.11-.08-.11-.08c.02-.1-.01-.14-.1-.12-.08-.02-.15-.07-.2-.14-.02-.03-.05-.04-.09-.05-.12-.07-.21-.11-.27-.12l-.33-.27-.34-.27c-.15-.12-.25-.22-.3-.29-.1-.13-.23-.34-.38-.64l-.16-.46-.02-.07-.05-.08s-.02.02-.08.05c-.05.14-.19.37-.41.7-.03.06-.09.15-.15.26-.04.1-.09.18-.15.23-.05.05-.12.14-.18.25-.02.1-.05.17-.08.21l-.23.31-.51.71-.35.55s-.04.05-.05.09c0,.04-.03.07-.05.09-.06.16-.17.3-.35.42l-.2.15-.47.65-.47.65s-.1.09-.2.15l-.05.09-.18.22-.14.2c-.03.06-.08.12-.14.2-.03.06-.08.12-.14.2v.06s-.4.57-.4.57c-.03.06-.12.19-.25.4-.11.22-.18.35-.22.41-.04.08-.09.18-.16.29-.05.12-.08.21-.09.27l-.2.48-.22.71c-.03.06-.08.11-.13.17-.04.08-.08.17-.12.27-.03.06-.06.07-.08.05,0-.02,0-.04-.02-.07ZM236.37,62.83s-.05-.03-.08-.08l.08-.05.07.11-.07.02ZM238.5,62.24s.03,0,.04-.02c.08-.16.15-.27.21-.35l.06-.12-.02-.07v-.06s-.03.06-.03.06l-.08.08-.2.32c-.01.06-.01.11,0,.13,0,.02,0,.03.02.04ZM241.99,54.88s.03,0,.04-.02c.02-.02.04-.05.05-.09v-.06s0,.03,0,.03l-.09.11v.03ZM247.02,62.35l.03-.13c.02-.08.06-.12.12-.1l-.12.24s0,.01,0,.03c0,0-.01,0-.03,0v-.03ZM248.45,59.65l-.02-.07-.08.08v.03s.1-.04.1-.04ZM255.95,65.95c-.1-.02-.19-.08-.25-.19l-.12-.06c-.15-.03-.26-.11-.34-.24-.08-.04-.14-.1-.19-.17-.07-.08-.17-.13-.29-.16-.03.02-.07,0-.13-.03-.06-.03-.11-.06-.15-.06l-.37-.28c-.11-.22-.24-.39-.41-.51-.11-.09-.2-.14-.26-.15-.1-.02-.16-.1-.18-.24-.03-.07-.14-.17-.33-.3-.15-.1-.3-.32-.45-.65-.03-.07-.09-.31-.17-.72-.01-.13,0-.25.04-.35h-.03s.17-.33.17-.33c.08-.16.12-.27.14-.33l.12-.24c.05-.03.1-.09.13-.17.04-.08.06-.13.07-.15-.05-.08-.06-.13-.03-.17.05-.05.08-.09.09-.11.05-.14.13-.26.24-.34.1-.15.2-.34.32-.55.04-.1.14-.24.29-.43.06-.07.24-.31.54-.7.11-.19.21-.35.3-.46.09-.13.17-.25.24-.34.14-.14.28-.32.41-.53.13-.08.21-.21.24-.37l.06-.12.14-.2s.04,0,.07-.02c.02-.02.04-.04.05-.06l.08-.08c.24-.3.38-.49.42-.56.11-.13.22-.25.31-.36.09-.13.17-.24.23-.31l.36-.45c.03-.06.1-.16.2-.32.1-.15.2-.28.31-.39.14-.17.24-.31.29-.43l.3-.46c.08-.07.14-.13.17-.19.04-.08.07-.14.1-.17.01-.06.07-.15.16-.26.05-.01.06-.04.05-.09.01-.06.01-.11,0-.13l-.16-.17s0-.04-.02-.07c0-.04.03-.07.05-.09.02-.1.02-.18-.01-.23v-.06s.04-.13.04-.13c-.01-.15.05-.23.18-.22.05-.03.13-.06.25-.08.27-.05.51-.14.71-.27.04,0,.07-.02.08-.08l.41-.67s.04-.08.03-.13c0-.04.03-.09.07-.15.03-.04.08-.1.14-.2.09-.11.18-.18.27-.2.18-.11.38-.15.61-.1.21.05.36.09.46.13.1.04.19.13.27.26.06.03.11.08.17.13.05.06.11.1.17.13.01.05.06.1.13.16.09.06.16.11.2.14l.23.28c.03.05.08.08.14.1.22-.02.4-.05.55-.11.48-.11.94-.19,1.36-.23.33-.1.65-.17.96-.19.29-.05.52-.05.69-.01l.22.05.28.06s.07.03.15.06c.08.02.14.06.17.13.02.03.04.04.09.05.04,0,.08.03.12.06.02.03.05.04.09.05.02,0,.03.02.02.04h-.03s-.04,0-.07.01c0,.02,0,.03,0,.03l.02.07-.04.02v.1s.22.08.22.08c0,0,.02.03.05.08.02.03.03.06.04.11.02.03.03.07.04.14-.01.06,0,.11.04.14.04.03.06.06.08.08.02,0,.04.06.06.18.04.03.06.06.08.08.04.03.06.06.08.08.07.1.07.2,0,.3-.03.13-.06.22-.09.27v.19c0,.09-.02.17-.06.25l-.17.36-.14.2h-.06c-.03-.06-.02-.13.04-.2.03-.02.04-.05.05-.09.01-.06.01-.11,0-.13l-.04-.14s-.06-.08-.14-.1c-.02,0-.04.01-.05.06l-.04.06v-.06s0-.07,0-.13l-.19-.04-.09-.02c-.06-.03-.14-.05-.25-.05-.32.06-.56.1-.71.11-.27.05-.68.12-1.22.19-.45.04-.77.07-.98.12-.11.02-.28.05-.51.09-.22.02-.41.02-.56.01-.07,0-.15.02-.24.05-.07,0-.15.02-.24.05-.13.01-.2.02-.2.02-.13.01-.24.01-.33,0-.02.02-.07.03-.14.04-.06-.01-.1,0-.1.01l-.1.14-.39.57c-.06.07-.15.18-.26.3-.09.11-.17.23-.24.34-.15.19-.26.34-.33.45-.09.11-.19.22-.3.33-.09.11-.18.23-.27.37l-.13.14v.03s.06.01.06.01l.41-.08c.13,0,.24.03.34.07.04.03.16.07.37.11.06.01.1.05.11.12.02.03.05.04.09.05.17.1.28.16.32.17v.06s-.05,0-.05,0c-.02,0-.03,0-.04.02,0,.02-.02.03-.04.02.02,0,.03.02.02.04,0,.02,0,.03.02.04l.21.08h.03s.1.13.1.13l-.14.04c-.08-.02-.14-.02-.16,0h-.03s0,.03.02.03l.09.05.31.07s.1.04.17.1c.02.11.06.19.12.22l.18.07c.06.03.08.07.07.11,0,.02-.02.03-.04.02l-.24-.12h-.06s.03,0,.02.02c0,.07.04.13.09.18.08.04.14.07.17.1l.23.31s0,.01,0,.03c0,0,0,0,.03,0l-.09-.02s0-.03-.02-.04-.03,0-.03,0c0-.09-.02-.11-.05-.08-.02.02-.05.02-.07.02v.13s.13.16.13.16c0,0,0,.01,0,.03.02.03.04.04.06.04-.04,0-.08-.04-.11-.09h-.03s-.02-.01-.06-.02v.1c.17.08.27.15.32.23l.11.25.05.08s.03.06-.02.09c-.03.02-.06.02-.1.01l-.17-.13-.26-.15c-.07-.06-.1-.03-.08.08v.03s-.03-.04-.03-.04c-.01-.05-.06-.07-.15-.07l-.99.02-.92.03-.27.04c-.33.02-.65.02-.95.02-.11,0-.22,0-.33.03-.11,0-.24,0-.39-.02-.04,0-.12,0-.23.02-.11,0-.22-.01-.32-.04l-.11.04c-.17.27-.29.44-.37.51l-.16.13c-.18.22-.38.49-.6.79-.09.11-.18.24-.28.4-.07.14-.18.28-.32.42-.33.54-.54.89-.62,1.04-.04.08-.08.17-.12.27-.04.08-.07.18-.1.31-.04.08-.01.12.07.11.07-.03.13-.04.17-.03.07,0,.11,0,.13,0h.03s-.03.01-.04.03l-.35.09s-.04,0-.07.02c0,0-.01,0-.03,0l.12.03.26.02h.06s-.04.04-.04.04l-.3.03c-.07,0-.11.03-.14.07-.03.02-.04.06-.03.13,0,.02,0,.04-.01.06.02,0,.03.02.02.04,0,.04.03.07.11.09l.26.02c.07,0,.14-.01.23-.02.11-.02.22-.02.33,0h.06s.04.02.06.03c.04,0,.07.03.09.05.07.1.13.14.21.11l1.04-.1.44-.07h.06s.11.02.2,0c.09-.02.18-.04.27-.04.05-.01.12-.03.21-.05.12-.04.23-.06.34-.06.02,0,.17-.02.44-.07.13-.01.24-.04.31-.06.09-.02.17-.04.24-.05.17.02.26.01.26,0l.05-.06s.03.02.02.04c0,.02,0,.03,0,.03.08-.05.1-.03.09.05.02.03.04.04.06.04.04,0,.06,0,.07-.02h.03s.06.02.06.02v-.03s.02-.06.02-.06c0-.02.02-.03.04-.02v.03s-.03.09-.03.09c0,0-.02.02-.08.05v.06s-.02.04-.03.06c.02,0,.03.02.02.04.02.03.07.08.16.17.02,0,.03.02.03.04.05.18.1.28.16.3.02,0,.03,0,.04-.02.03-.02.05-.02.07-.02l.04-.02s0,.01,0,.03c.02,0,.04,0,.06.01v.03s-.03.13-.03.13c.02,0,.06,0,.11-.04.05-.03.08-.06.08-.08,0,0,0-.01,0-.03.02-.02.04-.04.04-.06.02,0,.03.02.02.04,0,.02,0,.03.02.04v.03c-.06.03-.08.08-.07.15.02.03.02.07,0,.13.02.11.07.16.17.13.07,0,.12,0,.16.03.04.1.02.2-.07.31-.1.04-.14.11-.14.2,0,.09,0,.14,0,.16l-.07.31-.04.02s-.01,0-.03,0-.03-.02-.02-.04c-.06-.03-.09-.09-.1-.15-.01-.05-.03-.06-.06-.04-.11.11-.27.16-.49.16-.11.02-.25.03-.4.04-.13.01-.28.04-.44.07-.13.01-.28.05-.45.1h-.03s-.08-.04-.13,0c-.05.03-.09.05-.11.04l-.04.02-.12-.03c-.04.06-.09.09-.15.1-.07,0-.11,0-.13,0h-.2c-.13,0-.25.07-.33.18h-.03c-.06-.02-.15-.02-.26,0-.11.02-.2.03-.27.04l-.28.07s-.06,0-.11.04c-.06-.01-.09-.02-.09-.02h-.06c-.06-.03-.14-.02-.23,0-.1.04-.18.07-.25.08l-.15.07-.24.05-.09-.02ZM255.55,63.41l.08-.05h-.06c-.06-.03-.11-.02-.14.02l-.04.02h.06s.1,0,.1,0ZM254.25,60.64l.06-.12s0-.03-.02-.04v.03s-.05.06-.07.12h.03ZM255.86,63.34c.1.02.18.03.22.02h.03s-.02-.03-.02-.03l-.23.02h-.03s0,0,0,.02c.02,0,.03,0,.04-.02ZM254.51,60.2c.05-.03.08-.08.1-.14v-.03s-.02,0-.02,0l-.09.11v.06s.02,0,.02,0ZM258.15,64.43s.06-.05.08-.05c.02,0,.04,0,.07-.02l.38-.08c.06.01.14,0,.23-.02l.04-.06-.07.02c-.22,0-.39.01-.5.06-.05.03-.12.06-.21.08-.02,0-.04.01-.05.06h.03ZM258.27,63.83c.14-.04.27-.06.41-.08s.25-.03.34-.06l.07-.02s-.06-.01-.06-.01l-.43.04s-.11.03-.18.06c-.05.01-.11.03-.18.06h-.03s.03,0,.03,0h.03ZM259.45,63.56c.15-.01.28-.04.38-.08l.12.03-.15-.07c-.14.06-.26.09-.35.09,0,0,0,.01,0,.03,0,0-.01,0-.03,0h.03ZM267.72,52.97v-.06c.03-.06.05-.1.07-.12h.03s-.08.22-.08.22h-.03s0-.04,0-.04ZM263.79,66.59s-.09-.03-.15-.06c-.08-.04-.14-.07-.17-.1-.06-.03-.1-.06-.11-.09-.04-.03-.06-.06-.08-.08v-.03s-.01-.06,0-.1,0-.08-.01-.1c.01-.06,0-.12-.03-.17-.05-.06-.09-.1-.11-.12l-.02-.07s0-.1,0-.16c0-.07,0-.12.03-.16.01-.06.04-.13.08-.21.02-.1.07-.21.14-.33l.23-.44c.06-.1.14-.22.21-.38.03-.04.07-.09.13-.17.04-.08.09-.13.17-.16l.14-.04c.14-.04.22-.05.24-.05h.26c.21.04.36.11.44.22l.09.05s.08.04.11.09c.06.03.11.05.16.03.02,0,.05.03.08.08.01.05.05.08.11.09l.15.07s.06.03.05.08c-.01.06-.01.12,0,.16l.02.07.06.04s.05.03.08.08l.18.23.12.22-.05.06-.07.02c-.09.02-.2.11-.32.26l-.09.11s-.03.05-.02.09c.02.03.04.04.06.04s.04.02.06.04c.02.03.02.05.02.07l-.08.08-.15.07c-.05.03-.09.05-.11.04-.06-.01-.1.01-.11.07,0,.04-.02.06-.05.06l-.02-.07h-.03s-.02.02-.04.02c-.02.1-.07.15-.13.14v.06s-.03.06-.03.06c0,.04-.03.08-.06.12-.03.02-.06.02-.1.01l-.07.02c-.08.05-.12.07-.15.07-.07,0-.15.04-.25.11l-.21.05v-.03c-.08-.02-.19-.02-.32,0l-.28-.06ZM264.03,65.63s.02-.03.04-.02c0-.02,0-.03,0-.03-.02,0-.03,0-.03,0v-.06s.02-.03.02-.03h-.06s-.05.04-.05.04l.07.11ZM263.8,65.35c.1.02.2,0,.28-.07l.04-.06s.01,0,.03,0c0,0,0-.01,0-.03h-.03c-.06-.02-.09-.04-.09-.06h-.06s0,.02,0,.02c.03.05.03.07-.01.06-.1.07-.15.1-.15.1l-.04.02h.03ZM264.56,65.45l-.05-.04c-.05.03-.08.06-.08.08h.03s.11-.04.11-.04ZM264.83,65.9c-.03-.05-.02-.07.05-.06v-.03s.01-.03.01-.03h-.03s-.07.02-.08.04c0,.02-.02.04-.04.06v.06s.05.01.05.01l.04-.06ZM265.39,65.56s.07.04.09.02c.02,0,.03,0,.04-.02,0-.02,0-.03-.02-.04v-.19s.02-.03.02-.03c0,0-.01,0-.03,0,0,0,0,.01,0,.03v.03s-.05.06-.05.06c-.04-.03-.06-.03-.06-.01.02.03.03.04.03.04v.06s0,.07,0,.07ZM265.46,65.25s.02-.02.08-.05l-.02-.07-.08.08s.03.02.02.04ZM265.57,65.01s.06,0,.11-.04v-.03s.12-.07.12-.07l-.02-.04-.08.05s-.02.03-.04.02v-.03s.02-.06.02-.06l-.07.02s0,0-.03,0c0,0,0,.01,0,.03-.02,0-.03,0-.04.02v.03s-.02.06-.02.06c.02,0,.03,0,.03,0,0-.02,0-.03,0-.03l.04-.02h.03s-.03.08-.05.09Z\"><\/path><path class=\"cls-1\" d=\"M10.21,63.65l.22-.12s-.09,0-.22.12Z\"><\/path><path class=\"cls-1\" d=\"M63.07,31.16s.03-.02.05-.04c-.03,0-.05.04-.05.04Z\"><\/path><path class=\"cls-1\" d=\"M19.03,59.09s-.01.04-.03.06l.03-.07v.02Z\"><\/path><path class=\"cls-1\" d=\"M12.51,68.21c2.06-2.48,2.88-2.82,4.93-5.46.53-.57,1.07-1.2,1.6-1.81.53-.61,1.06-1.22,1.58-1.81.3-.79,1.41-1.43,1.85-2.26l.35-.09c.16-.3.36-.57.65-.71v.06c.25-.41.67-.69.79-.9v.06s.39-.39.39-.39l-.03.12c.46-.67,1.07-1.18,1.61-1.61l-.18-.14c1.24-.8,1.41-1.53,2.6-2.15v.06c.49-.81,1.07-1.14,1.65-1.47.3-.17.58-.33.88-.56.15-.12.28-.23.42-.39.15-.14.27-.31.42-.49-.14.2.14.04.14.1.6-.55,1.26-1.1,1.05-1.48.48-.35.45-.17.59-.07-.09-.16.26-.53.64-.81l-.13.2,1.03-.82-.38-.17c.62-.31.37.28.86-.17l-.15-.26c.81-.49,1.52-.4,2.37-.7.4-.25.81-.51,1.22-.78.41-.27.81-.55,1.2-.84.81-.57,1.62-1.11,2.42-1.68.81-.55,1.64-1.05,2.47-1.5.83-.45,1.67-.81,2.51-1.1l.23.14c.19.28.67-.91.92-.66l.31-.33c.12,0,.37-.03.21.12.35-.15.33-.21.54-.43h.44c.71-.22,1.32-.55,1.92-.92.61-.37,1.23-.72,1.96-.99.47-.07,1.01-.26,1.62-.47.59-.21,1.22-.48,1.86-.75l.47-.21c.15-.08.32-.13.47-.21.32-.13.62-.29.92-.42.6-.27,1.13-.56,1.6-.75.65-.35,1.35-.58,2.1-.77.74-.17,1.52-.28,2.28-.4l.58-.09.58-.07c.39-.05.76-.13,1.15-.2.37-.07.74-.17,1.11-.28.37-.09.72-.23,1.06-.38.1.02.32-.13.32-.17.44-.09.88-.19,1.32-.26l1.32-.24s.2-.04.52-.11c.32-.07.79-.17,1.32-.26.52-.11,1.1-.22,1.67-.35.13-.04.29-.08.42-.11.13-.04.29-.08.42-.09.27-.08.54-.13.78-.21.98-.28,1.64-.63,1.42-.99-.11-.18-.45-.36-1.09-.55-.31-.08-.71-.19-1.19-.28-.24-.04-.5-.09-.78-.13-.28-.04-.58-.07-.91-.11l.05-.08c-.75.03-1.36.08-1.92.19-.54.11-1.01.3-1.47.58-.26-.42-1.22.18-1.58.12l.03-.04c-.81.55-1.91.13-2.68.64.03-.04,0-.18.21-.24-.6.21-1.44.54-1.54.3-.37.11-.77.23-1.19.34-.42.11-.84.25-1.24.38-.81.27-1.54.55-1.95.91l.05-.1c-.45.45-.67.27-1.23.6-.04-.02-.09-.02-.09-.04-.24.24-.66.37-1.08.5-.4.13-.81.25-1.02.38l-.08-.16-1.14.44.44-.11c.01.26-.24.26-.57.27-.32,0-.75.05-1.11.36-.39.11-.71.51-1.01.88-.16.2-.32.37-.49.51-.18.14-.36.25-.58.27-.31.37.2-.49-.29-.08-.1-.24.21-.26-.02-.4-.51.35-1,.14-1.63.59l-.09-.18c-.75.73-1.75.51-2.21,1.1-.84.56-.83-.27-1.61.55l-.46-.07c-.42.15-.17.44-.65.55-.04-.16-.61.15-.42-.13-.56.13-1.02.48-1.55.83-.51.35-1.09.7-1.82.87-.15.46-.87.64-.97.98-.09-.12-1.31.72-.72.03.05-.06.16-.12.18-.06v-.22c-.44.03-.75.29-1.04.56-.29.27-.57.59-.93.78.24-.08.52-.25.39-.01l-.68.37.07-.24c-.35.17-.7.35-1.03.52l.23.1c-.52.21-.85,0-1.27.62-.17.3.58-.05.1.34-.35.15-.8.33-1.25.54-.45.21-.92.44-1.35.7.18.14-.04.3-.23.47l-.13-.16c-.73.83-.52-.17-1.27.62v-.18s-.02.52-.02.52c-.57.89-.62-.07-1.18,1,.31-.27.37.26-.08.48v-.24c-.19.2-.24.32-.4.39.08-.2-.07-.3-.38,0l.1-.38-.44.77c-.59.19-1.2.98-1.54.89,0,0-1.07.7-1.15,1.14.1-.32-.49.07-.44-.23-.15.38-.83,1.14-1.25,1.22l.05-.08c-.63.39-1.07.86-1.49,1.31-.42.45-.82.9-1.39,1.23.18.14-.42.51-.12.64-.21.3-.45.51-.7.69-.25.2-.48.33-.69.49-.41.29-.7.59-.63,1.11-.42.47-.67.33-.91.52l.08-.14c-.79.88-1.02,1.14-1.65,1.73-.25.37-.06.74-.65,1.22.07-.32-.12-.06-.33.15.11-.16.12-.24-.21-.04,0,.08-.04.16-.09.24,0,0-.03,0-.04-.02-.3.39-.2.38-.04.24,0,.02.04.04.12.02-.49.19-.95,1.04-1.19.86-.47.57-.83,1.1-1.18,1.63-.17.26-.33.51-.51.77-.17.26-.33.51-.51.77-.19,0-.08-.32.12-.64l-.53.71c-.13-.16.25-.47.39-.71-.45.27-.75.75-1.05,1.24-.3.49-.61,1.01-1.11,1.36l-.05.32-.07.04c.05.06-.03.36-.13.52-.22,0-.27-.32-.64.17-.22.12-.41.41-.59.73-.19.34-.36.69-.51.97.23-.26.23-.1.18.08-.18.24-.41.25-.5.49l-.18-.14c.23.06-.32.81-.31.97-.22,0,.18-.48.14-.63-.72.98-.37.49-1.07,1.5-.26.65.23.06.19.46-.3.49-.51,1.07-1,1.5h.27c-.51.97-.88,1.5-1.45,1.95-.43.97-.68,1.78-.88,2.4-.19.61-.29,1.07-.32,1.41-.07.66.14.78.43.66.59-.23,1.56-1.45,1.56-1.45.5-.59.93-1.1,1.3-1.63.37-.53.68-1.06.99-1.62.66-1.09,1.26-2.33,2.35-3.83l-.05-.02Z\"><\/path><path class=\"cls-1\" d=\"M13.5,74.16l-.09-.08s.04.08.09.08Z\"><\/path><path class=\"cls-1\" d=\"M9.94,72.13v-.02s-.02,0-.02,0l.02.02Z\"><\/path><path class=\"cls-1\" d=\"M13.42,71.58c-.95.1-1.31-.26-2.23.16-.47.09-.92.32-1.37.48-.13.37-.58.17-.76.51l-.14-.16c-.06.12-.14.21-.26.13v-.06c-.09.17-.26.13-.31.23v-.06s-.15.08-.15.08v-.08c-.18.21-.41.29-.63.28l.08.22c-.51-.11-.52.4-.99.24v-.06c-.32.74-.9-.13-1.23.58.05-.1-.06-.1-.08-.16-.21.13-.44.27-.3.7-.16.06-.17-.08-.25-.24.06.18-.05.31-.18.37l.03-.1s-.07.04-.08.06l-.03.04-.08.06c.04.12.08.24.12.35-.14-.06-.11-.43-.19-.32l.02.31c-.07,0-.14-.12-.18-.26-.04-.14-.05-.33-.08-.45-.07,0-.15.06-.28.17-.13.11-.29.27-.47.4-.07-.08-.04-.39.21-.74l.23-.17c.16-.11.05-.04-.07,0-.11.06-.23.09-.08,0-.05,0-.1.02-.13.02.07-.04.11-.1.18-.09.01-.04-.03,0-.12,0,.07-.04.13-.08.2-.09.08-.08.03-.12-.01-.2,0,0-.04-.04-.04-.06,0-.06,0-.14-.01-.2,0-.14-.01-.27.03-.41.44-.58.21-1.93.09-2.69-.35-1.1.89-2.07.46-3.23.05-.02-.04-.14-.07-.14l.1-.95s.09-1.17-.16-1.93c-.24-.77-.8-1.11-2.07.45l-.07-.04c-.18.48-.22.82.07,1.21-.39,0-.06.41-.19.52h-.03c.29.36-.29.58-.03.93-.03,0-.14-.04-.14-.12.03.23.1.55-.12.52.03.55-.13,1.25.19,1.66l-.05-.04c.23.24.01.25.13.49-.03,0-.05,0-.07,0,.22.26-.02.62.08.8h-.15s-.01.41-.01.41l.04-.16c.41.14-.29.27-.05.62-.09.27.8.76.56,1,.18.18-.3-.2-.16.06-.22-.04-.12-.12-.29-.12.08.24-.25.29-.14.56h-.17s.05.08.06.12c0,.02,0,.04,0,.06,0,.02,0,.06,0,.08-.01.12-.06.21-.1.33-.09.21-.16.43-.04.58.05.23-.1.35-.21.48-.11.12-.2.27-.07.49-.09.12-.19.23-.28.35-.07.29.29,0,.12.37-.16.08-.18.45-.3.37-.16.43-.13.74-.11,1.03.02.31.03.62-.26,1.34.16-.09.17,0,.17.12,0,.12.01.23.13.14-.06.1-.1.25-.13.41.13-.02.27-.05-.18.33-.05.04-.1.06-.08.04,0,0,.01-.04.03-.06l-.21.23c-.01.06-.05.1-.06.14.06.12.33-.05.59-.26.27-.21.55-.46.73-.49-.07-.04-.25.05-.03-.18l.35-.11-.2.25.51-.11.04-.23c.1,0,.14.12.21.16.07.04.18,0,.41-.25.11-.13.07-.19.05-.23-.02-.06-.02-.1.12-.19.29.02.79.03,1.3-.09-.03-.23.1-.27.23-.37v.2c.5-.5.23.37.76-.06l-.03.16c.03-.16.05-.31.06-.47.19-.27.26-.19.36-.15.02,0,.05.02.07.04,0,0,.03,0,.05,0,.03,0,.06-.08.09-.23-.1.08-.19-.39-.02-.35v.2c.09-.06.09-.15.15-.13-.01.12.07.27.16.2v.25s.09-.41.09-.41c.23.14.41-.19.56.03,0,0,.39,0,.39-.31-.02.19.2.2.21.41.02-.23.24-.48.42-.3v.04c.44.09.58-.52,1.01-.37-.08-.22.14-.15.01-.41.3-.38.84.37.73-.55.16-.09.26.14.36.16l-.03.06c.29-.17.39-.19.62-.24.09-.12,0-.53.24-.48-.02.18.06.12.14.1-.05.04-.05.1.09.18,0-.06.01-.1.03-.12,0,0,0,.02,0,.04.11-.1.08-.14,0-.14,0-.02,0-.06-.06-.1.19.18.38-.11.48.15.38-.17.59-.54.9-.73.07.14.01.27-.06.35l.23-.11c.04.2-.11.15-.17.21.37.26.49-.48.91-.26l.02-.18h.02c0-.06.02-.19.07-.23.09.18.09.41.26.38.18.14.34-.17.5-.3-.1,0-.09-.12-.06-.2.08-.02.18.14.22.04l.06.24c-.08-.22.17-.29.16-.41.09.18-.09.17-.08.33.33-.09.16-.06.5-.15.14-.21-.08-.22-.04-.45.15-.08.27-.29.48-.17l-.09-.2c.26-.23.44-.23.69-.05.93-1.08.95-1.7.71-2.05-.24-.36-.71-.44-.71-.44-.99-.31-1.34.41-2.36.8v.06Z\"><\/path><\/g><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d317eb elementor-widget elementor-widget-image\" data-id=\"0d317eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"885\" height=\"929\" src=\"https:\/\/arthroseactive.be\/wp-content\/uploads\/2026\/02\/arthrose-active-mushroom-1.webp\" class=\"attachment-full size-full wp-image-4015\" alt=\"\" srcset=\"https:\/\/arthroseactive.be\/wp-content\/uploads\/2026\/02\/arthrose-active-mushroom-1.webp 885w, https:\/\/arthroseactive.be\/wp-content\/uploads\/2026\/02\/arthrose-active-mushroom-1-286x300.webp 286w, https:\/\/arthroseactive.be\/wp-content\/uploads\/2026\/02\/arthrose-active-mushroom-1-768x806.webp 768w\" sizes=\"(max-width: 885px) 100vw, 885px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e506d81 e-con-full e-flex e-con e-parent\" data-id=\"e506d81\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-95da811 elementor-widget elementor-widget-heading\" data-id=\"95da811\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"> E\u00e9n ding is zeker:<br \/>Artrose Active kan rekenen op een hechte gemeenschap en krijgt alle steun <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-954941a elementor-widget elementor-widget-spacer\" data-id=\"954941a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4d5a3cf e-con-full e-flex e-con e-child\" data-id=\"4d5a3cf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-802f28d elementor-arrows-position-inside elementor-widget elementor-widget-n-carousel\" data-id=\"802f28d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;carousel_items&quot;:[{&quot;slide_title&quot;:&quot;Diapositive N\\u00b01&quot;,&quot;_id&quot;:&quot;6721dd3&quot;},{&quot;slide_title&quot;:&quot;Diapositive N\\u00b01&quot;,&quot;_id&quot;:&quot;808521a&quot;},{&quot;slide_title&quot;:&quot;Diapositive N\\u00b01&quot;,&quot;_id&quot;:&quot;ef73248&quot;},{&quot;slide_title&quot;:&quot;Diapositive N\\u00b01&quot;,&quot;_id&quot;:&quot;ff2929c&quot;},{&quot;slide_title&quot;:&quot;Diapositive N\\u00b01&quot;,&quot;_id&quot;:&quot;b46e85a&quot;}],&quot;slides_to_show&quot;:&quot;5&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:5,&quot;sizes&quot;:[]},&quot;slides_to_show_tablet&quot;:&quot;2&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;speed&quot;:500,&quot;arrows&quot;:&quot;yes&quot;,&quot;image_spacing_custom_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-carousel.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-carousel swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"swiper-wrapper\" aria-live=\"polite\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"1\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 van 5\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b53b7ef e-flex e-con-boxed e-con e-child\" data-id=\"b53b7ef\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b02a050 e-con-full e-flex e-con e-child\" data-id=\"b02a050\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d51b2ba elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"d51b2ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/arthroseactive.be\/wp-content\/uploads\/2026\/03\/kiomed-medecin-_0000_Jean-Francois-Kaux-768x1127-1.png\" title=\"kiomed-medecin-_0000_Jean-Francois-Kaux-768&#215;1127\" alt=\"kiomed-medecin-_0000_Jean-Francois-Kaux-768x1127\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc7366f elementor-widget elementor-widget-heading\" data-id=\"fc7366f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Dr. Jean-Fran\u00e7ois Kaux <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc30a89 elementor-widget elementor-widget-text-editor\" data-id=\"cc30a89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Hoogleraar aan de Universiteit van Luik en afdelingshoofd in het Universitair Ziekenhuis van Luik, specialist in<br\/>fysische geneeskunde en sporttraumatologie, erkend expert op het gebied van de behandeling van tendinopathie\u00ebn en referentiearts voor het Belgisch Olympisch en Interfederaal Comit\u00e9<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"2\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 van 5\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-737b791 e-flex e-con-boxed e-con e-child\" data-id=\"737b791\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-77a6502 e-con-full e-flex e-con e-child\" data-id=\"77a6502\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e9d2b3d elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"e9d2b3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"110\" height=\"110\" src=\"https:\/\/arthroseactive.be\/wp-content\/uploads\/2026\/03\/kiomed-medecin-_0004_practionner_17307347842.png\" class=\"attachment-large size-large wp-image-4017\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39a86bd elementor-widget elementor-widget-heading\" data-id=\"39a86bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Prof. dr. Jacques Bentin, MD, PhD<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-488c40c elementor-widget elementor-widget-text-editor\" data-id=\"488c40c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Geaggregeerde voor het hoger onderwijs in medische wetenschappen.<\/p><p>Voormalig kliniekhoofd reumatologie in het CHU Brugmann, internist, reumatoloog. <\/p><p>Universitair diploma in artroscopie en sportgeneeskunde.D.U. en arthroscopie et m\u00e9decine du sport.<\/p><p>Gespecialiseerd in echografie van het musculoskeletale stelsel, een discipline die hij heeft onderwezen aan het H\u00f4pital de la Piti\u00e9-Salp\u00eatri\u00e8re in Parijs.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"3\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 van 5\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c7cd61 e-flex e-con-boxed e-con e-child\" data-id=\"7c7cd61\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-127b129 e-con-full e-flex e-con e-child\" data-id=\"127b129\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f16ac33 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"f16ac33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"110\" height=\"110\" src=\"https:\/\/arthroseactive.be\/wp-content\/uploads\/2026\/03\/kiomed-medecin-_0001_owskkq22f9kmtqx5zbri.png\" class=\"attachment-large size-large wp-image-4018\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c0027fd elementor-widget elementor-widget-heading\" data-id=\"c0027fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Prof. Camille Choufani<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d86215 elementor-widget elementor-widget-text-editor\" data-id=\"5d86215\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Orthopedisch chirurg in Toulon en actief lid van de SFTS en de SFA. Prof. Camille Choufani is een specialist in sporttraumatologie en het herstel van kraakbeenletsels, en is sterk betrokken bij wetenschappelijk onderzoek. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"4\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 van 5\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0691e5f e-flex e-con-boxed e-con e-child\" data-id=\"0691e5f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1584bb4 e-con-full e-flex e-con e-child\" data-id=\"1584bb4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c41157a elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"c41157a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"110\" height=\"110\" src=\"https:\/\/arthroseactive.be\/wp-content\/uploads\/2026\/03\/kiomed-medecin-_0002_Krik-Heusdens.png\" class=\"attachment-large size-large wp-image-4019\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-acb5b24 elementor-widget elementor-widget-heading\" data-id=\"acb5b24\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Prof. Krik Heusdens <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4653ac elementor-widget elementor-widget-text-editor\" data-id=\"e4653ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p> Prof. Heusdens is orthopedisch chirurg aan het Universitair Ziekenhuis van Antwerpen (UZA) en hoogleraar aan de Universiteit van Antwerpen. Hij is gespecialiseerd in kniechirurgie en sporttraumatologie en richt zijn onderzoek op innovatieve technieken voor gewrichtsbehoud, zoals knie-distractie en herstel van het voorste kruisband.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"5\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 van 5\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-91e750e e-flex e-con-boxed e-con e-child\" data-id=\"91e750e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-61ef723 e-con-full e-flex e-con e-child\" data-id=\"61ef723\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1747c8f elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"1747c8f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"110\" height=\"110\" src=\"https:\/\/arthroseactive.be\/wp-content\/uploads\/2026\/03\/kiomed-medecin-_0003_Van-Overschelde2.png\" class=\"attachment-large size-large wp-image-4020\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e59beca elementor-widget elementor-widget-heading\" data-id=\"e59beca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Dr. Philippe Van\nOverschelde<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f9eec7c elementor-widget elementor-widget-text-editor\" data-id=\"f9eec7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Dr. Philippe Van Overschelde is orthopedisch chirurg op de afdeling \u201cHip &#038; Knee\u201d van het AZ Maria Middelares in Gent en oprichter van het medisch centrum Latem. Hij is gespecialiseerd in prothese- en sportchirurgie van heup en knie en combineert zijn klinische praktijk met expertise op het gebied van biomedische techniek.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Vorige\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Volgende\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-80e0129 e-con-full e-flex e-con e-parent\" data-id=\"80e0129\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2d2f775 e-con-full e-flex e-con e-child\" data-id=\"2d2f775\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e8eb3f5 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"e8eb3f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Beoordeel uw traject bij actieve artrose<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-38be304 e-con-full e-grid e-con e-child\" data-id=\"38be304\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-eb7cc71 e-con-full e-flex e-con e-child\" data-id=\"eb7cc71\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-57e422b e-con-full e-flex e-con e-child\" data-id=\"57e422b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4b3cf87 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"4b3cf87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Quiz<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-de70d04 elementor-widget elementor-widget-heading\" data-id=\"de70d04\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Mijn Arthrose Active traject<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67e34e2 elementor-widget elementor-widget-text-editor\" data-id=\"67e34e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Deze quiz helpt je te bepalen welk type traject het beste bij jou past, zodat we je vervolgens op maat gemaakte inhoud kunnen aanbieden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bcd39e4 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"bcd39e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/arthroseactive.be\/nl\/quiz-mijn-actieve-artrose-traject-beter-bepalen\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Doe de quiz \u201cMijn traject\u201d<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cdbaa38 e-con-full e-flex e-con e-child\" data-id=\"cdbaa38\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-fd1ff52 e-con-full e-flex e-con e-child\" data-id=\"fd1ff52\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-62acfe0 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"62acfe0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Quiz<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e236cf elementor-widget elementor-widget-heading\" data-id=\"1e236cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">hardnekkige artrose<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0932fd0 elementor-widget elementor-widget-text-editor\" data-id=\"0932fd0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Heb ik te maken met moeilijk te behandelen artrose?<\/p><p>Sommige mensen blijven pijn en beperkingen ervaren ondanks verschillende goed gevolgde behandelingen. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f1cf7b elementor-align-left elementor-widget elementor-widget-button\" data-id=\"5f1cf7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/arthroseactive.be\/nl\/quiz-hardnekkige-artrose\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Doe de quiz \u201cMoeilijk te behandelen artrose\u201d<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Onze aanpak Artrose Active is onze manier om te zeggen: artrose is geen eindpunt, maar een uitdaging die we beter kunnen begrijpen, anticiperen en behandelen, zodat u het vertrouwen in uw bewegingsvermogen terugvindt. Over ons Artrose Active is een redactioneel platform van KiOmed Pharma, een Belgisch bedrijf dat zich inzet voor onderzoek naar en de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-4597","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/arthroseactive.be\/nl\/wp-json\/wp\/v2\/pages\/4597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arthroseactive.be\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/arthroseactive.be\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/arthroseactive.be\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/arthroseactive.be\/nl\/wp-json\/wp\/v2\/comments?post=4597"}],"version-history":[{"count":20,"href":"https:\/\/arthroseactive.be\/nl\/wp-json\/wp\/v2\/pages\/4597\/revisions"}],"predecessor-version":[{"id":6214,"href":"https:\/\/arthroseactive.be\/nl\/wp-json\/wp\/v2\/pages\/4597\/revisions\/6214"}],"wp:attachment":[{"href":"https:\/\/arthroseactive.be\/nl\/wp-json\/wp\/v2\/media?parent=4597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}