{"id":4544,"date":"2025-03-13T14:01:36","date_gmt":"2025-03-13T13:01:36","guid":{"rendered":"https:\/\/arthroseactive.be\/de-stappen-in-het-traject-voorafgaand-aan-een-knieprothese-is-er-echt-alles-geprobeerd\/"},"modified":"2026-05-08T16:49:03","modified_gmt":"2026-05-08T14:49:03","slug":"de-stappen-in-het-traject-voorafgaand-aan-een-knieprothese-is-er-echt-alles-geprobeerd","status":"publish","type":"post","link":"https:\/\/arthroseactive.be\/nl\/de-stappen-in-het-traject-voorafgaand-aan-een-knieprothese-is-er-echt-alles-geprobeerd\/","title":{"rendered":"De stappen in het traject voorafgaand aan een knieprothese: is er echt alles geprobeerd?"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4544\" class=\"elementor elementor-4544 elementor-838\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7bc5239 e-con-full e-flex e-con e-parent\" data-id=\"7bc5239\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-8cf05d1 e-con-full e-flex e-con e-child\" data-id=\"8cf05d1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-78d1751 e-con-full e-flex e-con e-child\" data-id=\"78d1751\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-31f0fb4 e-con-full e-flex e-con e-child\" data-id=\"31f0fb4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4e14071 elementor-widget elementor-widget-post-info\" data-id=\"4e14071\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-inline-items elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-853d5bb elementor-inline-item\" itemprop=\"datePublished\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-date\">\n\t\t\t\t\t\t\t\t\t\t<time>13\/03\/2025<\/time>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-83836ee elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"83836ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">De stappen in het traject voorafgaand aan een knieprothese: is er echt alles geprobeerd?<\/h1>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9275dd5 e-con-full e-flex e-con e-child\" data-id=\"9275dd5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c80886 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"4c80886\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Het zorgtraject bij knieartrose: een stapsgewijze behandeling\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6742993 elementor-widget elementor-widget-text-editor\" data-id=\"6742993\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Artrose is een van de meest voorkomende gewrichtsaandoeningen: meer dan 650 miljoen mensen wereldwijd zijn ermee geconfronteerd, waaronder bijna 10 % van de personen ouder dan 60 jaar. <span style=\"font-weight: 400;\">1,2<\/span> In de ontwikkelde landen behoort ze zelfs tot de tien meest invaliderende aandoeningen. <sup>3 <\/sup>De knie, een sleutelgewricht in het dagelijks leven, is bijzonder kwetsbaar.<\/p><p> <\/p><p> <span style=\"font-weight: 400;\">Artrose kan hier om verschillende redenen ontstaan: door een trauma, of door genetische, metabolische of biomechanische factoren.<sup>4 <\/sup>Maar in tegenstelling tot wat vaak wordt gedacht,<\/span> <b>leidt het zorgtraject niet automatisch tot een prothese<span style=\"font-weight: 400;\">.<\/span><\/b><\/p><p> <\/p><p><span style=\"font-weight: 400;\">De behandeling is gebaseerd op een <strong>combinatie<\/strong> van niet-medicamenteuze en medicamenteuze behandelingen, met een duidelijk doel: <strong>pijn verlichten en de functie behouden<\/strong>.<sup>3<\/sup> Chirurgie komt pas in beeld nadat de conservatieve behandelingsmogelijkheden zijn onderzocht en geoptimaliseerd.3,4<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-be077eb elementor-absolute elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"be077eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Calque_2\" data-name=\"Calque 2\" viewBox=\"0 0 104.69 124.18\"><defs><style>      .cls-1 {        fill: #2d2c78;      }    <\/style><\/defs><g id=\"Calque_1-2\" data-name=\"Calque 1\"><path class=\"cls-1\" d=\"M15.64,20l-.08-.14s-.06-.17-.13-.36l-.08-.2s-.07-.13-.11-.27c-.02-.04-.02-.1-.02-.16-.02-.07-.03-.12-.05-.16,0-.06.03-.1.07-.12.05-.04.07-.1.08-.19,0-.06.01-.12.01-.16l-.07.03v-.16s.05-.03.12-.09c.02,0,.02,0,0-.03-.04-.02-.05-.05-.03-.07l.1-.09v-.06s-.06,0-.06.03c-.05.08-.1.13-.14.15,0,.02-.01.03-.03.03v-.03c.06-.19.11-.3.16-.34.07-.06.15-.17.25-.33l.11-.21v-.1s-.07,0-.09.02-.05.04-.07.06c-.02.04-.05.08-.07.12-.1.16-.23.43-.39.8,0,.02,0,.04,0,.06-.03.04-.03.07,0,.1.04.05.05.11.05.2-.03.08-.04.15-.05.19l-.04.06-.03-.03s0-.03,0-.03c-.02,0-.03,0-.03,0-.02-.02-.04-.02-.06,0-.02.02-.03.02-.03,0-.02-.02-.02-.04,0-.06,0-.02,0-.04,0-.06l-.03-.03c-.15-.06-.19-.15-.14-.27l-.03-.07s-.03,0-.03.03h-.03s0-.08-.02-.1v-.03s-.06.03-.06.03v.03c-.07.06-.11.09-.11.09l-.09-.1s-.02-.04,0-.06c.05-.08.04-.14-.02-.16,0-.04-.02-.07-.06-.07l-.04.06s0,.03,0,.03c-.02,0-.03,0-.03,0l-.03-.03.02-.26.21-.56c.03-.1.09-.2.18-.27l.47-.6c.15-.2.32-.34.52-.4l.41-.32c.07-.08.16-.13.27-.14.11-.03.19-.06.23-.08l.36-.07s.06.02.06.04l-.04.06-.04.12s.06.04.12.04c.04,0,.09,0,.13-.02.12-.16.18-.27.19-.34v-.06c.01-.11.08-.21.19-.3h.03s-.03.05,0,.1c.02.04.01.08,0,.1-.07.02-.08.07-.05.16.02.02.03.07.02.13-.02.04-.04.07-.04.09v.13s.02.01.02.03l.19-.3s0-.05,0-.1-.01-.09-.05-.13l.03-.03c.08.03.15-.02.21-.14l.27-.49.27-.52.11-.12s.01-.04.04-.06c.05-.04.06-.08.04-.12v-.03c.07-.02.09-.05.07-.09-.02-.04-.03-.08-.02-.1,0-.06,0-.1,0-.1.09-.06.16-.17.22-.33v-.06s-.06.03-.06.03l-.18.27-.11.12v-.16s.15-.5.15-.5l.03-.03c.06,0,.11-.01.13-.05.02-.04.04-.07.04-.09l.37-.55.34-.61.11-.18.89-1.4c.15-.24.25-.43.31-.55.02-.04.04-.1.05-.19-.03-.13-.01-.24.06-.32l.33-.52s.08-.06.1-.06c.16-.07.29-.23.39-.48l.56-.88.46-.86.56-.85c.39-.57.71-.98.94-1.23l.75-.9.04-.06h-.06s-.26.04-.26.04c-.04.02-.1.01-.16-.01-.02-.04-.05-.07-.09-.07-.04,0-.08,0-.1.02-.09.04-.15.04-.19.02,0,0-.02,0-.06,0h-.1c-.21-.03-.43-.16-.64-.42-.1-.12-.18-.19-.24-.21-.14-.1-.22-.28-.24-.54v-.1c.06-.06.12-.15.19-.27.08-.14.17-.24.28-.3l.34-.26c.23-.15.47-.24.73-.26l1-.11c.19-.03.49-.02.9.01l.19.02.7.09c.34.03.6.04.77.03.17.01.43.02.77,0,.15.01.28,0,.39-.06.07-.04.16-.05.29-.04l.19.02c.6,0,1.15.16,1.66.47l.37.16c.08.05.11.11.08.17-.05.06-.03.13.05.2.04,0,.07.02.09.04.02.02.13.1.33.22.12.05.29.15.49.3.08.05.13.08.15.08.08,0,.14.08.17.21,0,.09.03.17.11.27.1.12.16.29.18.53.02.22.05.37.09.46.02.04.02.12.01.23-.01.15-.06.28-.13.41-.19.41-.45.75-.8,1.02l-.59.53-.1.09c-.11.03-.23.11-.37.22-.14.1-.25.17-.34.23-.34.23-.51.34-.51.34l-.59.46c-.16.14-.31.21-.44.22-.13.05-.21.09-.23.11l-1.02.68-.51.31-.77.41-.77.41-.17.08.15.08c.63.18,1.08.34,1.37.47.23.11.56.28,1.01.54.18.12.36.29.53.5.02.02.02.05,0,.1,0,.02,0,.03.03.03l.15.11.12.14.09.1s.08.1.11.17c.06.05.11.12.14.21l.25.44c.04.07.04.12.02.16-.07.08-.07.17,0,.26.19.23.28.53.24.89-.02.21-.09.51-.21.88-.14.42-.38.84-.72,1.29-.12.14-.32.35-.6.62-.51.49-1.14.95-1.89,1.38l-1.28.69s-.1.03-.16.05c-.07.02-.13.04-.2.08-.02.02-.06.03-.1.02h-.06s.04-.07.04-.07l.3-.17s.02-.02.07-.06l-.1.02-.1.06c-.09.06-.37.17-.83.35-.11.03-.21.07-.3.1-.09.04-.17.06-.23.08-.07.06-.1.04-.09-.04l-.13.05c-.11,0-.12.02-.04.09v.03s-.2.05-.2.05v-.03s-.01-.05-.06-.04l-.46.15-.43.16h-.06s.03-.03.03-.03l.03-.03h-.06c-.07.01-.13.03-.2.04-.07.02-.14.03-.23.04h-.03s.03-.03.03-.03c.04,0,.16-.04.36-.13.4-.12.8-.28,1.2-.51l.53-.21c.09-.04.15-.07.17-.11,0,0,.02-.02.07-.06l.1-.02v-.06s-.06,0-.06,0c-.02,0-.04,0-.07.03-.02.02-.06.03-.1.02-.06,0-.16.02-.3.07-.13.05-.24.08-.33.07-.04,0-.06,0-.07.03-.12.1-.3.18-.57.24-.11.03-.21.07-.3.1-.09.04-.17.06-.23.08l-.2.08c-.07.02-.15.03-.26.04s-.2.05-.27.11l-.13.05c-.09.04-.2.06-.33.07-.11.03-.22.08-.33.13l-.59.11-.43.12-.68.1c-.11.05-.23.09-.36.1-.04.02-.1.03-.16.05-.04.02-.11.02-.19.02-.17,0-.33.02-.49.05-.13.03-.25.05-.36.07l-.42.06-.06-.04.07-.03.26-.04.72-.13.62-.14.04-.06s-.06,0-.06,0c-.09.01-.2.01-.35,0l-.12-.04s.01-.04.04-.06c.04-.02.08-.03.1-.02.02,0,.06,0,.13-.02.06,0,.13.02.19.05h.1s.04,0,.07-.02c.02,0,.04.01.06.04.04.05.07.05.1,0,.04-.02.08-.03.1-.02,0,0,0-.01,0-.03.02-.02.02-.03,0-.03-.06-.09-.02-.13.11-.12l.43-.12c.08.05.16.05.23-.01.02-.02.12-.05.3-.1.04,0,.06,0,.06,0,.02,0,.03-.02.04-.06,0,0,0-.01,0-.03,0,0-.01,0-.03,0h-.06s-.03-.07-.03-.07c0,0,0-.01,0-.03,0,0,.01,0,.03,0,.2-.07.32-.11.36-.13.02-.02.06-.03.1-.02l.04-.06h-.06s-.33.06-.33.06l-.13.05-.03-.03s0-.01,0-.03c0,0,.01,0,.03,0v-.06s-.03,0-.03,0l-1.44.26c-.26.06-.48.09-.65.07l-.13.02h-.03s.01-.03.03-.03c.02-.02.07-.03.13-.02.07-.02.15-.03.26-.04.13-.01.23-.03.3-.07h.1s.17-.04.17-.04l.03-.03-.06-.04h-.16s-.16-.03-.16-.03l.23-.04.89-.28h.03s.13-.05.13-.05h-.16c-.31.07-.61.1-.91.1l-.13.02c-.13.05-.28.07-.45.06l-.45.06c-.11,0-.17.02-.2.08h-.06c-.09,0-.2,0-.35,0-.04,0-.08,0-.1.02-.09.04-.16.05-.23.04-.11.01-.27,0-.48,0-.08,0-.14,0-.16.05,0,0-.01,0-.03,0-.02.02-.03.02-.03,0-.11,0-.17.03-.2.11,0,.02-.03.05-.07.09-.02.04-.04.08-.04.12,0,.04.03.08.09.1l.06.07-.07.03c-.06,0-.1.03-.11.12.03.17-.03.26-.18.27-.05.04-.08.06-.1.06-.06-.03-.1,0-.1.09,0,.04,0,.13,0,.26,0,.15.05.28.13.4v.06s-.07-.04-.07-.04ZM15.38,18.89s.04-.05.04-.09l-.02-.1-.1.09v.06s.02.07.02.07l.07-.03ZM15.97,19.51s-.03-.01-.03-.03c0,0-.02-.02-.06-.07h.03s.12.08.12.08l-.07.03ZM15.03,18.08l-.06-.04-.03.03.03.03.07-.03ZM14.91,17.98s.06-.07.04-.09c-.04-.07-.03-.13.02-.19l-.03-.03h-.03s-.08.18-.08.18v.06s0,.01.02.03c.02.04.04.06.06.04ZM14.64,17.38l-.06-.04v.03s0,.06,0,.06l.07-.06ZM15.52,18.42s.02-.07.04-.09h-.03s-.04.05-.04.09v.03s.03-.03.03-.03ZM14.66,17.15s.02-.07.04-.09h-.03s-.04.09-.04.09h.03ZM15.07,17.28v-.03s-.03,0-.03.03l-.09.25h.03s.09-.25.09-.25ZM15.61,17.75s.04-.06.04-.12v-.06s-.03,0-.03,0c0,.02,0,.03,0,.03-.02.04-.04.09-.05.16h.03ZM15.77,17.41s.02-.07.04-.09h-.03s-.04.05-.04.09h.03ZM16.04,16.5l.15-.24s0-.03-.03-.03h-.03c-.09.03-.15.11-.18.24l.03.07.07-.03ZM16.77,16.53s.07-.07.07-.09c.02,0,.03-.03.04-.09-.05.04-.07.06-.07.06l-.07.09v.03s.03,0,.03,0ZM16.34,15.98s.08.05.13.01c.18-.11.28-.23.29-.36-.02-.02-.03-.06-.02-.1l-.1.02c-.09.08-.14.12-.14.12-.09.06-.14.13-.15.21v.1ZM17.24,16.32h-.06c-.07.01-.11.05-.14.11l.06.04.14-.15ZM17.32,16.16s.01,0,.03,0c0,0,0-.01,0-.03.07-.06.13-.12.18-.18.03-.06.06-.11.11-.15l.11-.21-.05-.13s-.07.06-.07.06c-.07.08-.13.19-.19.34-.07.12-.13.21-.15.28v.03s.03,0,.03,0ZM19.83,18.66c-.06-.07-.05-.11.01-.13l.13-.02h.03s-.04.06-.04.06c0,0-.02,0-.07.03-.02.02-.03.05,0,.1l-.06-.04ZM17.94,15.35s-.07-.07-.09-.07c-.05.04-.08.06-.1.06,0,.04.02.07.06.07l.13-.05ZM20.39,17.75l-.19.02s-.01.03-.03.03l.06.04.17-.08ZM17.98,14.9s.06-.03.1-.02l.03-.03.29-.39v-.1s.02-.1.02-.1l-.02-.13-.1.09s-.04.05-.04.09c-.02.04-.05.09-.08.15-.03.06-.06.12-.11.18,0,.02-.03.07-.08.15v.1ZM18.83,15.11v-.06s-.03,0-.03.03l-.04.06s0,.03,0,.03c.02,0,.03,0,.03,0l.04-.06ZM17.63,14.42v-.03s0-.03,0-.03c.02-.02.04-.04.04-.06,0-.04.02-.07.04-.09.05-.04.07-.08.07-.12l.38-.64.03-.03v.06s-.36.71-.36.71l-.15.28s-.03,0-.03.03l-.03-.07ZM20.02,14.98s.07-.07.07-.09c-.04,0-.07.02-.07.06v.03ZM18.6,13.96s.03-.02.04-.06l.45-.76.15-.24-.03-.07-.03.03c-.07.1-.1.19-.09.28-.04,0-.06,0-.07.03l-.44.67s-.04.04-.04.06c.02.02.03.05.03.07h.03ZM24.17,18.62v-.03c.09-.04.16-.05.2-.05l-.17.08h-.03ZM24.37,18.54s.03-.05.07-.09c.18-.07.31-.13.4-.19l.03.03v.03s-.03,0-.03,0c-.07.04-.14.06-.23.08-.07.04-.15.08-.24.14ZM16.87,17.99c.13-.01.36-.03.68-.07.3-.02.57-.06.81-.12.57-.19,1.09-.32,1.55-.41l.63-.2c.55-.19,1.17-.41,1.86-.67.29-.08.53-.17.73-.26.44-.18.78-.32,1-.43.4-.14.73-.31,1.01-.52.05-.04.09-.07.14-.08.07-.04.12-.07.17-.11l.17-.11.14-.12.89-.6c.41-.31.67-.51.76-.61.16-.14.3-.31.43-.51.05-.04.07-.09.08-.15,0-.06,0-.14-.01-.23,0-.11.03-.22.06-.35,0-.11.04-.17.08-.19.07-.04.11-.11.12-.21-.03-.37-.19-.66-.47-.88-.04-.07-.08-.08-.12-.04-.04,0-.1-.03-.19-.08l-.15-.08c-.48-.13-.82-.21-1.01-.25-.23-.06-.56-.13-.98-.21-.36-.07-.9-.14-1.62-.21-.06,0-.11,0-.13.02l-.1.02-.15.24-.4.48c-.07.12-.12.19-.15.21l-.21.24v.06s0-.03,0-.03c.02,0,.03,0,.03,0h.03s.03.02.03.04c-.02.04-.07.11-.15.21-.05.1-.12.17-.21.21-.11.05-.2.13-.28.23-.05.08-.1.17-.15.28-.02.02-.04.04-.04.06.02,0,.04,0,.07-.03l.07-.03v.06c-.11.16-.2.27-.29.33-.04.02-.15.12-.31.29-.05.04-.06.08-.04.12.06.07.04.12-.05.16-.11.01-.17.08-.18.21.02.07-.02.16-.12.28-.05.12-.12.19-.21.21-.04,0-.09,0-.13.02-.02.02-.05.04-.07.06-.09.06-.13.14-.12.25v.03c0,.06-.02.11-.05.12,0,.02,0,.05,0,.1l-.09.28-.22.33s-.08.06-.1.06c-.07.02-.1.06-.11.12-.05.1-.11.17-.18.21-.11.03-.17.12-.18.27.02.07,0,.14-.05.22,0,.02-.02.05-.04.09-.02.02-.01.04.03.07v.06c-.05.04-.11.1-.18.18-.07.08-.15.13-.24.14h-.06s.03-.01.03-.03c0-.02.01-.04.04-.06.05-.04.03-.07-.06-.1l-.03-.07.11-.15.07-.09s0-.03-.03-.03c0,0,0,.01,0,.03l-.07.03-.07.03s.02-.07.04-.09c0-.04.03-.06.07-.06.13-.01.2-.09.21-.24.03-.15.1-.29.2-.43l.46-.83s.02-.03,0-.03c0-.02,0-.04,0-.06l.1-.09s0-.03-.03-.03l-.05.16s-.06,0-.07.03c-.05.06-.17.25-.37.58l-.07.09s-.01.03-.03.03v-.03s.08-.12.08-.12l.23-.43v-.1s-.02.05-.06.09l-.14.18c-.24.34-.38.55-.41.61-.12.18-.18.35-.17.5,0,.06-.02.09-.04.09-.07.04-.13.11-.18.21-.05.06-.09.08-.13.05l-.11-.17c-.04-.09,0-.14.08-.15l.07-.03-.04-.32h-.06s-.07.08-.08.15l-.07.03c-.09,0-.13-.02-.12-.04-.04-.05-.07-.05-.1,0-.02.02-.03.03-.03.03l-.14.08.08-.15-.02-.13-.13.05v-.06c-.04.06-.05.1,0,.13-.07.12-.11.19-.11.21-.05.06-.03.09.06.1l-.15.28-.04.06s.02.11-.05.19l-.55.43c-.16.14-.34.37-.54.69-.02.04-.03.07,0,.1,0,.02.02.03.06.04l.1-.02.06.04c.01.09.09.11.22.08ZM26.34,5.87c.09-.04.18-.08.27-.14.09-.08.21-.15.34-.23l.53-.24.92-.56.47-.28.34-.26.95-.56c.39-.24.64-.47.77-.67.12-.12.19-.25.23-.4,0-.09,0-.14-.05-.16-.02-.04-.06-.07-.12-.07l-1.24-.14h-.1c-.17-.02-.3.04-.4.18l-.21.14c-.4.37-.79.77-1.19,1.18-.07.08-.23.29-.47.63-.37.52-.58.82-.65.87-.12.14-.28.35-.47.63l-.07.12.16-.05ZM33.72,17.97c-.06,0-.13-.02-.19-.05-.04-.02-.09-.04-.16-.05-.04-.02-.09-.03-.16-.01-.06,0-.14-.02-.22-.05l-.37-.16h-.06c-.01-.09-.06-.16-.14-.21-.08-.05-.14-.1-.18-.14-.08-.05-.15-.1-.21-.15-.04-.07-.09-.11-.15-.14-.02-.04-.05-.09-.08-.14s-.08-.1-.11-.17l.06.04-.33-.64c-.09-.2-.14-.54-.14-1.01l-.11-.2s-.03-.05-.03-.07c.02-.04.04-.07.04-.09-.01-.34-.01-.57,0-.67.02-.28.05-.5.09-.67.02.22.03.38.02.48h.03c.01-.15,0-.35-.01-.61h-.03s-.02.07-.04.09c-.03-.11-.04-.28-.02-.52.02-.26.05-.46.08-.6.03-.13.11-.44.24-.94.03-.06.06-.16.09-.28.06-.15.09-.26.09-.35,0-.06,0-.13-.02-.19,0-.09.03-.17.05-.25.19-.5.39-.9.59-1.2.12-.18.23-.42.32-.71.05-.08.1-.16.15-.24.07-.1.15-.21.22-.33.05-.08.09-.17.12-.28.05-.12.12-.24.19-.34.1-.21.18-.34.23-.4.02-.04.04-.1.05-.19v-.03s.4-.54.4-.54l.38-.35c.19-.24.31-.39.36-.45.12-.12.24-.23.38-.32.16-.09.3-.2.41-.32l.55-.4c.21-.17.39-.28.54-.31.53-.21.93-.35,1.19-.41l.24-.14c.11-.05.26-.07.45-.06l.67.03c.13.01.24-.06.34-.23l.12-.21.03-.03h.03c.06,0,.11.04.15.11.06.05.1.1.11.17l.08.17c.01.09.05.16.11.23.06.07.11.13.15.17.02,0,.03.01.03.03-.05.04-.05.1-.02.19,0,.04.01.11.05.2l.03-.03s.04-.11.05-.22l.07-.03.49.24c.08.03.16.04.22.02.02-.02.06-.03.1-.02.06,0,.11.02.12.04.04.02.08.05.12.07l.03.03c.13.01.14.04.02.1l.35.09c.16.1.27.18.33.25.12.14.18.23.2.27.02.07.05.13.11.2.06.07.11.13.15.17v.13c.09.09.17.15.23.18s.13.01.2-.05c0,.11,0,.18.04.23.06.05.1.08.12.11.08.05.12.11.11.17,0,.04,0,.07,0,.1l.02.1c.12.29.17.59.15.91l-.03.67c-.03.34-.14.82-.32,1.45l-.26.78c-.11.29-.18.51-.22.66l-.09.35-.04.06v-.13s-.14.21-.14.21c-.05.1-.13.25-.23.43-.08.16-.19.36-.34.58-.39.5-.64.82-.76.96-.15.22-.3.41-.47.57v.1s.06,0,.06-.03c.02,0,.08-.01.16-.05-.07.12-.16.19-.24.2-.24.04-.42.19-.55.43-.03.13-.13.28-.3.46-.74.62-1.11.93-1.11.93,0,0-.3.25-.9.76-.02.02-.04.05-.04.09,0,.02-.01.04-.04.06l-.11.15-.19.34c-.12.12-.22.12-.32,0l-.12-.11-.07.03c-.33.34-.53.54-.6.62l-.11.18-.06-.07s-.02.02-.07.06l-.11.12-.12-.04s-.12.04-.24.14c0,.02-.02.03-.07.03-.02,0-.03,0-.03,0-.04-.07-.09-.09-.15-.08-.07.02-.12.02-.16.02-.17.03-.33.01-.48-.04-.02,0-.07,0-.16-.01-.06,0-.12.01-.17.05-.04.02-.11.02-.19.02l-.57-.08ZM31.54,14.67s-.01-.08-.05-.16h-.03c.06.07.09.12.08.16ZM33.11,16.15s.03-.02.03,0c.02,0,.04,0,.06,0l.42-.06s-.07-.07-.09-.07c-.04,0-.11,0-.19-.02-.08-.03-.16-.04-.22-.02-.04.02-.12.02-.23.01-.08-.03-.16-.04-.22-.02-.04,0-.09-.02-.16-.05-.04-.02-.07,0-.1.06h-.03c-.08-.03-.21-.1-.37-.2l-.24-.18c.04.09.09.16.17.21,0,.02,0,.05.02.1.02.02.05.02.1-.02.02.04.05.07.09.07.06,0,.09.02.09.04.02.02.05.04.09.04l.32.06-.06-.07.31.12.19-.02ZM33.18,16.45s-.08-.07-.12-.07v.03s.12.04.12.04ZM32.15,14.98l-.15-.11c.04.07.07.11.08.14h.06s0-.03,0-.03ZM31.8,14.95v-.06s.04.01.03.03c.02,0,.04.01.06.04-.01-.09-.06-.18-.14-.27-.06-.09-.07-.17-.04-.23l-.06-.1s0-.03-.03-.03c0-.06,0-.11-.02-.13l.12.07c-.05-.11-.08-.17-.08-.17-.03-.11-.07-.23-.1-.36h-.03s-.03-.05-.03-.07c0-.04,0-.08-.02-.1v.1s-.01.03-.01.03l.06.04s-.04.06-.04.12c0,.06,0,.18.03.36,0,.11,0,.17.02.19.05.18.13.35.24.53h.03ZM32.98,15.82c.11,0,.19.03.25.05v-.03s-.52-.27-.52-.27l.29.38-.02-.13ZM32.49,15.46l.06.04c.15.06.23.07.25.05.07-.02.12-.01.16.01.06.03.12.03.16.01.04-.02.11-.02.19-.02.08,0,.15,0,.19-.02l.06.04.16-.05.13-.05v-.03s.06-.02.1-.06l-1.57-.04-.03-.07s0,.03,0,.03l-.64-.35s.07.08.2.24c.04.05.08.08.12.11.06.03.11.05.15.08l-.13.02.09.07h.13s.22.09.22.09l-.02-.13ZM33.43,15.73s.06.03.06,0c0-.04,0-.07,0-.1l-.2.05.12.04ZM32.94,16.59c.06,0,.15.02.25.05.13.01.22,0,.29,0,.76-.08,1.35-.3,1.79-.65l.07-.12-.1.06h-.03c-.07.03-.13.07-.2.11-.05.04-.09.08-.14.12-.06-.07-.08-.05-.07.06-.02,0-.04,0-.06,0-.02-.02-.04-.02-.06,0l-.39.09-.04.06c-.06,0-.12,0-.16.02-.04,0-.11.01-.2.05l-.3.1c-.09.01-.16.02-.23.01-.04-.02-.08-.04-.12-.04h-.03c-.06,0-.11,0-.13.02h-.06s-.07.02-.07.02l-.02-.1s-.06.02-.1.06c-.02.02-.05,0-.09-.04,0-.02,0-.02-.03,0,0,.04,0,.06.03.07.08.05.15.08.22.08ZM34.4,16.07v-.03c-.06.02-.13.03-.19.05-.04.02-.09.04-.13.05v.03s.33-.1.33-.1ZM33.6,15.68c.22-.02.39-.03.52-.02-.12-.05-.22-.08-.28-.09h-.03c-.03.08-.09.1-.2.04l-.07.03.06.04ZM34.25,15.55s.02,0,0,0c0-.02,0-.03,0-.03-.04,0-.08,0-.1.02l-.07.03s.06,0,.06,0l.1-.02ZM34.08,15.34c.26-.06.56-.11.88-.15v-.03s-.87.12-.87.12v.06ZM34.87,15.5l-.03-.03s-.06.02-.1.06h.03s.1-.02.1-.02ZM35.58,15.79s-.03-.03-.03-.03c.02-.02.03-.04,0-.06l-.06-.04c-.09.08-.14.12-.14.12h.16s.06.02.06.02ZM36.76,16.95h-.03s-.06.01-.1.05c.02,0,.03.01.03.03l.1-.09ZM35.06,15.14s.08-.01.16-.05v-.03s-.16.08-.16.08ZM35.62,15.73s.03-.05.07-.09l-.06-.04-.04.06.03.07ZM35.01,14.97s.08-.01.16-.05l-.03-.03-.14.08ZM37.19,17.57s.08-.06.1-.06c0,0,.02.02.06.07h-.16ZM35.73,15.58s.04.06.06.04c.04-.02.08-.03.1-.02l-.09-.07h-.1s.03.06.03.06ZM35.47,14.88c.09-.04.23-.1.43-.19v-.03s-.47.22-.47.22h.03ZM36.15,14.84s-.03,0-.03,0c0-.02,0-.03,0-.03l.51-.28v.03s-.48.28-.48.28ZM33.89,16.03c.07-.02.15-.03.26-.04.11-.03.22-.07.33-.1.33-.12.6-.25.8-.38l.31-.2.23-.11.41-.32c.2-.11.34-.2.41-.25l.65-.46.38-.29s.17-.15.52-.44c.04-.02.07-.04.07-.06,0-.02.01-.04.04-.06.14-.12.21-.17.21-.17.07-.06.13-.11.17-.15.05-.06.1-.11.14-.15-.13-.01-.22.03-.27.14,0,0,0,.01,0,.03,0,0-.01,0-.03,0,0,.04-.08.14-.22.3l-.17.08-.17.08v-.03s-.07.15-.07.15l-.03-.07-.1.09s.02.03.06.04c-.05.04-.08.05-.1.02-.04,0-.1.02-.17.08-.05.04-.07.07-.07.09l-.04.09h-.06s.03,0,.03,0c0-.02,0-.03,0-.03-.02-.02-.07,0-.16.05-.07.06-.13.11-.17.15-.05.06-.09.1-.14.12-.04.02-.08.04-.1.06l-.17.15h-.06c-.25.17-.45.28-.61.33-.07.02-.14.06-.24.14v.03s.3-.1.3-.1c0,.02,0,.03,0,.03.02,0,.03,0,.03,0l-1.09.71c-.16.07-.33.14-.53.21-.2.07-.41.15-.63.23.02.02.04.02.06,0ZM35.97,14.67c.13-.05.26-.13.37-.22h-.06s.14-.09.14-.09c.02-.02.05-.03.07-.03.04-.02.07-.04.07-.06l.17-.08s0-.03-.03-.03l-.14.12c-.13.03-.22.07-.27.11v.06c-.09.04-.17.05-.23.04l.03.07.2-.08c-.13.07-.24.14-.31.2ZM36.79,14.42s-.06.03-.1.02h-.03s0-.03,0-.03l.02.1.1-.09ZM37.26,15.01s.08-.08.17-.11h-.03s-.05.03-.07.02c-.02,0-.04.02-.07.06v.03ZM36.8,14.39s.05-.03.07-.03c.04-.02.08-.05.1-.09.02,0,.03.01.03.03l-.17.08h-.03ZM37.03,13.89c.18-.07.3-.13.37-.19-.02,0-.03,0-.03,0,0-.02,0-.03,0-.03l-.34.26-.24.17s0,.03.03.03l.21-.24ZM38.28,14.68h-.03c-.16.13-.24.2-.24.2h.03s.24-.2.24-.2ZM35.61,15.83c.06,0,.11,0,.13-.02.2-.11.4-.24.58-.4.11-.05.25-.13.4-.22.16-.11.31-.21.44-.28l.07-.03.07-.12.38-.26.28-.26.66-.58.35-.32.07-.12.14-.15.18-.27c.14-.16.24-.28.29-.36v-.06s-.06,0-.06,0l-.07.12-.64.72c-.07.08-.15.16-.25.24-.07.08-.14.16-.21.24-.05.04-.1.1-.18.18-.05.06-.12.12-.21.17-.03.04-.08.08-.17.11l.03.03s-.02.07-.04.09c-.14.12-.26.2-.38.26l-.2.11s-.01,0-.03,0c0,0,0,.01,0,.03l.06.04-.07.06s-.11.08-.2.11c-.07.04-.15.08-.24.14l-.48.38s-.24.15-.64.39l-.07.06ZM36.66,14.89l.41-.32s.24-.17.79-.57l.52-.47s.07-.06.07-.12l.27-.2.14-.15.07-.12s.05-.04.07-.06c.02-.02.05-.04.07-.06l.11-.15s.09-.09.35-.39v-.06s-.06.03-.06.03l-.31.29c-.19.24-.32.39-.39.45-.05.06-.13.15-.25.27-.1.12-.19.21-.28.26,0,0-.36.3-1.07.9l-.59.46h.06ZM39.05,14.26v-.03s-.48.41-.48.41l.06.04.42-.41ZM39.5,13.59l-.07.03s0,.08.02.1l.04-.12ZM38.9,12.77l-.06-.07-.1.09s0,.03.03.03l.13-.05ZM39.23,13.41l.18-.18h.03s-.18.18-.18.18h-.03ZM38.53,12.87c.12-.1.27-.24.46-.44,0,0,0-.01,0-.03,0,.02-.01.03-.03.03-.11.08-.26.21-.45.41v.03s.03,0,.03,0ZM33.4,14.25c.09-.01.25-.05.49-.12.04-.02.09-.04.13-.05.07-.02.12-.02.16-.02.21.02.43,0,.65-.07.22-.09.37-.14.43-.16.22-.05.4-.12.53-.21l.68-.45.55-.37s0,.05,0,.1c.02.04,0,.09-.04.12-.02.04-.06.08-.11.12-.02.02-.05.05-.07.09l-.28.3c.06,0,.12-.01.16-.05l.18-.18s.06-.07.1-.09c.07-.02.11-.02.13-.02.13-.05.23-.11.3-.17.09-.08.18-.14.27-.2l.21-.24c.07-.06.15-.15.25-.27.05-.06.12-.12.21-.17.09-.08.14-.17.15-.28h.03s.14-.15.14-.15l.46-.51c.15-.2.29-.36.43-.48.02-.04.05-.09.08-.15.03-.06.07-.1.14-.12v-.06s.05-.09.05-.09l.03-.03-.03-.03s0-.06,0-.06l.25-.24-.2.05s.1-.08.17-.11c.07-.04.11-.09.14-.15,0-.02,0-.03,0-.03.02,0,.03,0,.03,0l.03-.03-.06-.04s-.01,0-.03,0c0,0,0-.01,0-.03v-.03s.04-.03.04-.03c.08.03.13,0,.14-.08,0,0,.03-.06.08-.19,0-.02,0-.03,0-.03l.04-.09c.05-.12.11-.27.17-.44.11-.31.19-.53.22-.66.06-.25.09-.43.08-.54,0-.04.02-.09.05-.16.03-.06.01-.13-.05-.2v-.03s.06-.07.04-.09c-.02-.02-.05-.04-.09-.04l-.35-.03.1-.09h-.1s-.03-.01-.03-.01h-.58s-.08.02-.16.03c-.07.02-.12-.02-.15-.11h-.03s-.05-.03-.1-.01c-.04,0-.08-.02-.12-.04-.15-.01-.28,0-.39.06l-.27.11.12.04c-.22.09-.36.15-.4.19l-.07.03c-.12.14-.21.23-.28.26l-.21.14-.33.1.03.07.29-.04s-.08.06-.1.06c-.07.02-.16.04-.3.07-.11.01-.2.04-.26.07-.02.02-.11.05-.27.11-.13.03-.24.12-.31.26l-.1.02s-.06-.03-.06-.07c0-.09,0-.15-.02-.19,0,0-.01,0-.03,0,0,0,0-.01,0-.03-.08,0-.17.02-.26.07-.07.06-.12.1-.14.12-.05.04-.08.06-.1.06-.02,0-.04,0-.07.03-.02.02-.04.04-.04.06-.05.08-.1.16-.15.24-.05.06-.1.13-.15.21-.55.89-.87,1.43-.98,1.62-.1.16-.31.57-.62,1.23-.03.08-.07.18-.12.28-.05.1-.09.17-.12.21l-.17.53-.34,1.35c0,.06.01.13.05.2.06.05.12.06.19.05ZM39.39,14.07c.12-.14.24-.27.35-.39.14-.14.27-.28.39-.42h-.03c-.09.1-.21.21-.35.35-.12.12-.25.26-.39.42l.03.03ZM39.59,13.7c.09-.08.16-.13.21-.14-.02,0-.03-.01-.03-.03-.07.02-.12.07-.18.18ZM39.11,12.53s-.04-.04-.06-.04c0-.02,0-.03,0-.03,0,0-.02.02-.07.06,0,.04.02.07.06.07l.07-.06ZM37.31,15.14l.07-.03.65-.49.04-.09.1-.06s.02-.03,0-.03l.07-.03.04-.12v.13c.04-.06.1-.12.17-.18.07-.06.11-.12.11-.18.04,0,.09-.01.13-.05.09-.04.2-.13.35-.29.07-.08.15-.17.25-.27.09-.1.19-.21.29-.33.07-.06.07-.1.01-.13l.03-.03.47-.57c.2-.28.32-.44.36-.48h.03c-.03.06-.07.12-.14.18.08.05.15.03.2-.05.07-.1.14-.2.19-.3.05-.12.12-.24.19-.34.08-.16.13-.27.16-.31,0-.02.03-.05.07-.09l.08-.19c.1-.21.15-.35.13-.44,0-.02.01-.03.03-.03.1-.14.13-.25.09-.31.05-.08.08-.14.08-.19l-.09-.07-.07.09c-.04.19-.11.42-.22.69h-.03s.04-.13.04-.13c-.05.04-.08.06-.1.06l.12-.25s.04-.11.05-.22c-.11.03-.17.06-.17.08l-.26.4c-.06.19-.13.37-.21.56v.1s.13-.15.13-.15v.1s.06-.06.06-.06c0,.04-.02.07-.04.09l-.12.21c-.05.06-.1.12-.14.18-.03.06-.06.12-.11.18-.05.08-.12.16-.21.24-.65,1.01-1.42,1.89-2.32,2.63.02.02.05.04.09.04l-.07.03h-.03s-.1.02-.17.08c-.07.04-.1.08-.11.12v.03s0,.06,0,.06h-.06s0-.07,0-.07l-.17.15.06.04-.07.03-.04.06-.06-.07-.14.15h.03s.03,0,.03,0c.02-.02.05-.03.07-.03l-.04.06h.03s.07-.12.07-.12ZM38.39,14.56l.27-.2s.06-.06.11-.12c.07-.08.14-.12.2-.11.02,0,.03,0,.03-.03.02-.02.05-.03.07-.03v-.03s-.1.02-.1.02h-.03s0-.01,0-.03c.07-.04.18-.12.34-.26v.03s-.21.21-.21.21l.06.04.32-.33s0-.04,0-.06c.02-.04.06-.08.11-.12,0,0,.09-.08.28-.23.14-.18.22-.27.22-.27l.36-.42.11-.15-.13.02.29-.39.06.07c.17-.24.32-.46.44-.67.12-.2.24-.39.34-.55,0-.02,0-.03-.03-.03,0,.04-.03.06-.07.06l.04-.12.12.04-.05-.13v.03s.01-.19.01-.19c-.02.02-.05.04-.07.06,0,0,0,.01,0,.03l-.34.55-.63.97-.08.15-.25.24-.57.69c-.07.08-.14.15-.21.21-.07.06-.13.12-.18.18l-.6.62-.28.26h.03ZM39.65,13s.06,0,.07-.03l.57-.69v.06s.1-.12.1-.12l.04-.06h-.1s-.07.02-.07.02l-.04.06c-.07.12-.26.36-.54.72,0,0,0,.01,0,.03,0,0-.01,0-.03,0ZM36.66,9.3c.07-.34.14-.59.19-.75.03-.06.07-.1.14-.12l.21-.17c-.14.12-.24.26-.29.42-.04.17-.07.29-.1.38-.05.12-.08.22-.09.28l-.07.03v-.06ZM36.23,7.98s.03,0,.03-.03l-.09-.04s-.01,0-.03,0c0,0,0,.01,0,.03.02.02.05.04.09.04ZM36.42,7.67s-.01,0-.03,0c0,0,0-.01,0-.03l-.18.24.06.04.15-.24ZM39.82,11.73l-.03-.03c-.05.08-.08.13-.08.15l.11-.12ZM39.69,11.39h-.03s-.17.14-.17.14c0,.02,0,.03,0,.03.02,0,.03,0,.03,0l.18-.18ZM39.35,12.01l.06.07v-.06c.05-.04.07-.06.07-.06l.14-.18.22-.37c.17-.24.27-.38.29-.42l-.93,1.11s0,.03,0,.03c.02,0,.03,0,.03,0l.11-.12ZM40.06,11.91s0-.03-.03-.03l-.11.12h.03s.1-.08.1-.08ZM36.55,7.56s0-.02,0-.06l-.07.03s-.03.05-.07.09c.02,0,.03.01.03.03l.1-.09ZM36.16,6.94h.03s-.06-.03-.06-.03l-.27.11.03.03.27-.11ZM40.56,12.47c.05-.06.07-.11.08-.15,0-.04.02-.07.04-.09v-.03s-.03,0-.03,0c0,.06-.02.12-.05.16-.02.02-.05.05-.07.09.02,0,.03.01.03.03ZM40.92,12.75s.05-.04.07-.06c.02-.02.04-.04.04-.06l.07-.12s-.01,0-.03,0c0,0,0-.01,0-.03l-.18.24s.03.01.03.03ZM40.14,13.23c.16-.11.25-.18.27-.2l.11-.12h.03c.05-.1.16-.25.33-.45.02-.02.04-.05.04-.09l.12-.21s0-.02,0,0c.02,0,.03,0,.03-.03l.1-.02s0-.05,0-.1c.03-.06.06-.12.11-.18l.15-.28.06.04s.05-.02.1-.06c-.06-.05-.09-.07-.09-.07,0,0,0-.01,0-.03.02-.02.04-.04.04-.06h-.06s-.05.18-.05.18l-.1.02s-.04.05-.04.09c0,.02-.01.04-.04.06-.05.12-.1.22-.15.28-.28.3-.5.57-.65.81l-.32.39v.03ZM36.85,7.45s0-.03,0-.03c.02,0,.03,0,.03,0l.14-.18v-.03c-.09.08-.15.14-.17.18,0,0,0,.02,0,.06ZM40.01,11.74s-.03,0-.03,0c0-.02,0-.03,0-.03h.03s.19-.3.19-.3l.25-.33v-.06s.04-.06.05-.12l.11-.18s-.12.12-.21.24c0,.02-.02.03-.07.03l-.06-.04c.06,0,.1,0,.1-.02.02-.02.04-.05.04-.09l-.1.06-.04.06-.3.52.03.07h.03s-.02.08-.04.1l-.11.12.03.03.1-.02ZM41.07,12.48c.16-.07.23-.17.22-.3-.05.06-.08.11-.11.15-.03.04-.06.09-.11.15ZM36.59,6.79s-.06-.07-.06-.07l-.07.06s0,.01,0,.03c0,0,.01,0,.03,0l.1-.02ZM41.21,11.66l-.11.15s.03.01.03.03l.08-.19ZM36.91,6.46c-.06,0-.12,0-.16.02l.03.03.13-.05ZM37.14,6.42v-.03s-.16.08-.16.08l.16-.05ZM41.43,11.32l-.03-.03-.11.15h.06s.07-.12.07-.12ZM36.85,6.75s.07.06.09.04c.02-.02.05-.04.07-.06.04,0,.08,0,.1-.02.02-.02.03-.03.03-.03.04.05.07.06.09.04.02-.04.05-.07.07-.09l.11-.12.06.04s0-.03,0-.03c.02,0,.03,0,.03,0,.13-.03.2-.05.2-.05.07-.02.11-.03.13-.05.05-.04.08-.07.1-.09l.1-.09v-.03s-.03,0-.03,0c-.07.02-.13.04-.2.08-.05.04-.1.07-.17.08-.06,0-.12.01-.17.05-.02,0-.04,0-.06,0,0-.02,0-.02-.03,0l-.13.05-.07.03-.23.04s-.05,0-.1.02c-.04.02-.05.05,0,.1l-.23.04v.03s.08,0,.12.01c.04-.02.08-.01.1,0ZM41.65,11.37l.04-.06-.12-.04s0,.01,0,.03c0,0-.01,0-.03,0l.03.03s.07.07.09.07v-.03ZM40.44,10.5c.07-.04.15-.12.25-.24.07-.12.11-.2.12-.25.03-.06.01-.14-.04-.23l-.23.46-.15.28.07-.03ZM40.47,10.15s.07-.06.07-.06l-.02-.13s.06.03.06,0c.02-.02.05-.04.07-.06-.02,0-.03,0-.03,0,0-.02,0-.03,0-.03-.05.04-.08.06-.1.06v.03s-.04.06-.05.12v.06ZM41.04,10.61l.07-.06.05.13-.03.03-.09-.1ZM41,10.03s.1-.12.15-.24c-.07.02-.13.07-.21.17l.03.07h.03ZM41.7,11.22c.07-.04.06-.08-.02-.13h.06s.06.02.06.04l.04-.12-.03-.07s.02-.03.07-.03c.02,0,.03,0,.03-.03.02-.02.04-.06.04-.12,0-.04,0-.08-.02-.1.13.01.16-.07.09-.25l-.09.25-.15.28h.03c-.05.08-.1.13-.14.15.02.02.03.07.02.13ZM41.87,10.3h-.03s-.26.42-.26.42l.06.04.23-.46ZM40.47,8.7c-.04-.09-.03-.14.01-.16.05-.04.08-.07.1-.09l-.12.25ZM41.88,10.27c.05-.12.11-.24.16-.34-.09.04-.13.06-.14.08v.13s-.03.07-.05.09c.02,0,.03.01.03.03ZM42.19,10.36l.08-.19.09-.31h-.03s-.27.55-.27.55l.03.03.1-.09ZM41.87,9.59s-.03-.01-.03-.03l-.11.12s.03.01.03.03l.11-.12ZM41.64,9.64s0,.01,0,.03c0,0,.01,0,.03,0l.04-.06-.12-.07.07-.03h.03s.06,0,.06,0c-.04,0-.06-.03-.06-.07,0-.04.03-.1.08-.19l-.05-.13s-.04,0-.07.03c-.02.02-.04.04-.04.06l-.09.28.02.19.1-.06ZM39.02,6.17c.06,0,.13-.01.2-.05.07-.04.11-.09.14-.15-.07.02-.14.04-.23.08-.07.04-.13.06-.2.08l.09.04ZM38.27,4.85v-.03s-.03-.03-.03-.03l-.17.11v.03s.2-.08.2-.08ZM41.85,9.08s.01-.03.03-.03l-.12-.07-.03-.03.07-.12s0-.02,0-.06l-.07.06-.05.16s-.02.07-.04.09l.16-.02.03.03ZM38.53,4.77l-.12-.07s-.06.02-.1.06c.04.05.06.07.06.07l.17-.05ZM42.02,9.67l.03.03v.06s.03,0,.03,0c0-.06.03-.14.08-.22h-.03s-.01,0-.03.03c0,.02,0,.04,0,.06,0-.02,0-.03-.03-.03.04-.17.09-.37.15-.6.08-.23.12-.43.12-.6l-.41,1.44.03.03.08-.22ZM41.81,8.75s0-.04,0-.06c.02-.02.03-.03.03-.03-.02-.02-.05-.04-.09-.04l.05.13ZM42.45,9.58v-.1c.02-.11.04-.19.06-.25h-.03s-.06.35-.06.35l.03.03v-.03ZM42.33,9.47c.06-.17.09-.29.1-.38h-.03s-.13.37-.13.37l.03.03.03-.03ZM39.67,5.68h-.1s-.03.02-.03.02c.06,0,.09.02.09.04l.04-.06ZM41.18,7.61l.02-.22h-.03s-.03,0-.03,0v.06c-.01.06,0,.11.02.13v.06s.03-.03.03-.03ZM42.6,8.95v-.1s-.02,0-.02,0l-.04.09.03.07.04-.06ZM38.57,4.74c.09-.04.16-.07.2-.11.04-.02.09-.04.13-.05.04-.02.1-.02.16-.02.02,0,.05,0,.1,0,.04-.02.07-.05.07-.09l.11-.12s.03,0,.03-.03c.02,0,.03,0,.03,0,0-.02,0-.03,0-.03h-.03s-.1.03-.16.05c-.04,0-.08.03-.1.09-.03.06-.12.11-.27.14l-.36.1s.07.07.09.07ZM41.94,8.06c0-.06.02-.09.04-.09v-.06s0-.03-.02-.03l-.07.09s.02.06.06.1ZM42.61,8.82s.03,0,.03-.03l.05-.25s-.08.04-.11.12c-.03.06-.03.12-.01.16h.03ZM40.06,5.68s.04-.1.05-.19h-.03s-.08.18-.08.18h.06ZM39.82,5.43s.02,0,.06,0l.1-.02s.06-.03.1-.02v-.06s-.26.04-.26.04v.03s-.04.03-.04.03c.02,0,.03,0,.03,0ZM42.16,8.85c.06-.25.13-.46.18-.63v.16s.02,0,.02,0l.1-.38s-.08,0-.1.02v-.03c.09-.01.12-.08.08-.19,0-.02,0-.04-.03-.07-.02-.02-.04-.05-.06-.07,0-.09,0-.15-.02-.19l-.21,1.36h.03ZM39.7,5.33s.1-.06.23-.11c.02-.02.07-.02.13.01.08,0,.15,0,.2-.05.13.01.16-.03.11-.12-.02,0-.05,0-.1,0-.02-.02-.04-.02-.06,0-.33.06-.53.09-.62.11h-.03s0,.03,0,.03c.02.02.04.04.06.04.04,0,.06.02.06.04v-.03s-.03.05-.04.09h.06ZM41.93,7.83s.07-.06.07-.06c.03-.04.03-.08.01-.13,0-.04.02-.08.04-.12,0-.04,0-.1-.02-.16-.01-.09,0-.15.05-.19l-.08-.14h-.03c-.11.05-.13.13-.05.22l.05.2-.04.06-.02.25.03.07ZM39.75,4.37v-.06s-.32.07-.32.07l.03.07.3-.07ZM40.88,5.81c.15,0,.3-.05.46-.12l-.12-.04.04-.06-.12-.04s0-.01-.03-.03c0-.02,0-.03-.03-.03-.02,0-.07,0-.16-.01-.08,0-.15,0-.2.05,0-.09-.03-.13-.12-.14-.06,0-.12-.02-.16-.05l.13-.02c-.06-.05-.13-.07-.22-.05-.08,0-.15,0-.2.05,0,.04,0,.06.03.07h.13s.06.05.12.05l-.05.16-.08-.2-.11.18s-.03.05-.07.09v.03s.06-.03.06-.03c.06.07.11.1.15.08.19.02.33.02.42,0l.12.04v.03ZM40.8,5.29h-.1s.09.1.09.1v-.1ZM42.7,7.8s.03,0,.03-.03l-.02-.19h-.03s.01.22.01.22ZM39.85,4.37c.06,0,.12-.01.17-.05v-.03s-.17.08-.17.08ZM39.97,4.16l-.06-.04-.08.15.03.03.11-.15ZM42.35,6.97l-.04-.23s-.01.03-.03.03l.02.19h.06ZM43.28,20.83s-.12-.1-.24-.15c-.02.04-.06.04-.1,0-.15-.06-.22-.13-.24-.21l-.08-.2-.05-.13v-.06s0-.08-.02-.1h-.03s-.01-.08-.05-.17c0-.02,0-.05-.02-.1,0-.02.02-.06.04-.12.02-.02.02-.08-.02-.19-.02-.04-.05-.05-.1,0v.03s-.03-.01-.03-.03c.01-.13,0-.22,0-.29,0-.02-.02-.06-.06-.1v-.06s.03.03.03.03h.03c0-.06,0-.09-.02-.1-.02,0-.03-.01-.03-.03,0-.06.02-.11.04-.12,0-.02,0-.05,0-.1v-.03s-.03.03-.03.03v.06s-.04,0-.04,0c-.02-.02-.03-.07-.02-.13-.02-.04-.01-.08,0-.1,0-.02,0-.04,0-.06h.03s.07-.07.07-.09c0-.02-.02-.06-.06-.1-.02-.04-.02-.11-.02-.19,0-.08.04-.18.09-.28.03-.1.05-.18.05-.22.03-.04.05-.09.08-.15.03-.06.06-.12.11-.18.05-.12.08-.2.08-.22v-.03s0,0-.03,0c0,0,0,.01,0,.03l-.11.21c-.05.08-.08.14-.08.19l-.07.03v-.06s.04-.1.09-.19c0-.06.03-.14.08-.22.03-.08.06-.16.08-.22.03-.06.05-.12.08-.19l.12-.28s.02,0,0,0c0-.02,0-.03,0-.03v-.06s.04-.1.09-.19v-.03s-.03,0-.03,0l-.04.06-.03.03v-.03s0,0-.03,0c0,0,0-.01,0-.03v.03s-.12.18-.12.18l-.03.03v-.03c.01-.08.03-.15.05-.19,0-.06.02-.11.04-.12.03-.04.05-.08.07-.12l.02-.19h-.03s-.03,0-.03.03l-.07.03s-.01,0-.03,0c0-.02.01-.03.03-.03,0-.08.03-.14.08-.15v-.03c.03-.08.07-.18.12-.28.05-.1.09-.17.12-.21.05-.08.08-.14.08-.19.02-.02.02-.03,0-.03,0-.02,0-.04,0-.06-.04,0-.06,0-.07.03,0,0-.02.02-.07.06v-.1s.08-.12.08-.12v-.03s-.03,0-.03,0c0,.04-.03.08-.07.12v.03s-.01-.03-.03-.03l.04-.12v-.03s-.03,0-.03.03c-.05.04-.07.09-.08.15-.02,0-.03,0-.03.03h.06s0,.02,0,.04c0,0,.01,0,.03,0-.02,0-.03,0-.03.03-.06-.03-.1,0-.1.09l-.29.39v-.03s.12-.25.12-.25c.1-.18.19-.37.27-.55l.23-.43.04-.06s-.06,0-.07.03l-.11.18-.04.06s.02-.06.04-.06l.35-.64c.12-.18.29-.48.49-.89l.26-.46c.08-.14.17-.3.26-.46.1-.18.19-.38.28-.59.03-.13.07-.23.12-.31s.09-.15.11-.21c.15-.29.26-.5.31-.65l.36-.77.27-.55c.11-.25.18-.43.21-.56l.11-.15c.16-.31.27-.58.36-.8.03-.08.09-.21.19-.37l.35-1.03.26-.46.12-.28.11-.18.07-.06c0-.06.04-.16.09-.28l.22-.27s.04-.05.04-.09c.05-.04.08-.06.1-.06.06,0,.14,0,.23-.04v-.03c.03-.06.05-.15.06-.25,0-.06.06-.11.17-.15.04,0,.08,0,.1-.02.02-.02.05-.04.07-.06,0-.02.03-.05.07-.09,0-.02.01-.03.03-.03v-.1s.07-.03.07-.03l-.03.03.03.07s.03,0,.03,0c0-.02,0-.03,0-.03.04,0,.06.02.06.04h.03s.03,0,.03,0v.03s-.11.15-.11.15v.1s.03-.06.03-.06c0-.02.06-.05.17-.08.02,0,.06,0,.13.01.09-.01.15-.05.2-.11l.03-.03.03.07s0,.08.02.1c.05-.04.07-.06.07-.06.02-.02.11-.12.25-.3.09-.04.15-.07.17-.11,0,0,.01,0,.03,0,.02,0,.03.01.03.03.02.07.07.08.16.05,0-.02.01-.03.03-.03l-.04.06s-.01.04-.04.06c-.02.02-.02.04,0,.06.02.02.06.04.12.04.08,0,.12-.03.11-.12,0-.04.03-.06.07-.06.06,0,.12-.01.16-.05.04-.02.1-.02.16-.02.06,0,.12.02.16.05,0,0,.02.02.06.07.02.04,0,.1-.05.16-.02.04-.04.07-.04.09,0,.04,0,.06.03.07v.03s-.14.08-.14.08v.06c.09.09.13.26.11.49l-.02.26c-.01.17-.08.4-.19.69-.03.15-.06.37-.09.67l-.02.19c-.02.26-.01.53.02.84.03.15.05.4.06.74.01.09,0,.17-.02.26,0,.09,0,.17,0,.26,0,.11,0,.27.02.48,0,.3.02.68.06,1.13l.05.87.04.68c.02.3.02.54,0,.71.01.34.01.6,0,.77,0,.02,0,.03.03.03-.01.13,0,.3.02.52l.05.16c.04.07.06.24.08.52,0,.04,0,.11-.02.19.02.07,0,.13-.05.19l.03.07.07-.03.19-.37.26-.46.22-.33.15-.24.25-.33.19-.3.12-.25s.09-.15.19-.34l.34-.61c.03-.06.05-.11.08-.15.03-.06.05-.11.08-.15l.15-.28.38-.71.16-.37.34-.61.31-.55.35-.68.49-.82c.05-.1.1-.19.15-.28.07-.08.12-.15.15-.21.1-.14.22-.36.38-.64l.34-.61.1-.09-.04.09-.2.4-.04.06c-.07.04-.13.14-.19.3,0,.02-.03.07-.08.15-.03.08-.09.21-.19.37-.05.08-.1.14-.14.18,0,0,0,.01,0,.03,0,0,.01,0,.03,0h.03s.08-.21.08-.21v.13s-.02.1-.02.1c-.02.02-.04.04-.04.06.02.02.05.03.1,0,.04-.02.06,0,.06.07-.02-.02-.04-.02-.06,0-.02.02-.03.03-.03.03v.06s.02.03.02.03c.07-.06.09-.1.07-.12.09-.04.13-.1.11-.18,0,0,0-.01-.03-.03,0-.04.03-.06.07-.06,0-.06.03-.09.07-.09.02,0,.03-.02.04-.06-.04-.05-.03-.07.04-.06v-.03s-.03-.03-.03-.03c.02-.02.04-.04.04-.06l.16-.34.11-.18s.07-.09.15-.21l.04-.06.09.04h.03s.03-.04,0-.06h-.03s-.1.02-.1.02l.08-.15.07-.03h.03s.05.05.1.01l.11-.15s.02-.06.04-.06l.04-.06v.06s-.16.34-.16.34l-.04.06s-.06.07-.04.09c-.02.02-.04.05-.04.09.02.02.02.04,0,.06v.03s-.01,0-.03,0c0,0,0-.01,0-.03v-.03s0-.03,0-.03v.03s-.08.12-.08.12c-.05.04-.04.07.02.1v.06c-.06.08-.08.15-.09.22,0,0-.01.02-.04.06,0,.02.02.03.06.04v.1s-.04,0-.04.03h.06s.11-.15.11-.15c.07-.08.16-.22.26-.43l.12-.25s0-.03,0-.03c.02,0,.03,0,.03,0v.03c-.1.14-.17.29-.2.43v.03s.03,0,.03-.03l.16-.31s.09-.13.18-.27c0-.02,0-.03,0-.03.02-.02.02-.04,0-.06,0-.02.01-.03.03-.03.02-.02.04-.05.04-.09l.03.03s-.04.04-.04.06c.02.02.02.04,0,.06-.02.02-.04.09-.05.22l.07-.03.12-.21s.09-.06.13-.05l.07-.03.04-.06-.03.03-.07.03s.02-.06.04-.06c0-.02.03-.05.07-.09h.03s.08-.15.08-.15c.02,0,.03,0,.03,0,0-.02,0-.03,0-.03.09,0,.13-.05.14-.18,0-.02.01-.03.03-.03.04-.02.08-.01.1,0,.08.05.14.07.19.05h.06s-.01.04-.03.03l-.28.26-.19.34s-.03,0-.03.03c.02,0,.03,0,.03-.03.04-.02.09-.07.14-.15l.11-.15c.03-.08.11-.15.24-.2.04-.02.09-.07.14-.15l.1-.09h.06s0,.1,0,.1l-.03.03h.03s.07-.01.07-.06c-.02-.02-.02-.03,0-.03.02-.02.05-.03.07-.03.06,0,.12-.04.17-.15,0,0,.09-.08.28-.23v.03s-.15.21-.15.21c-.03.06-.03.13-.02.19.04.05.07.07.09.07.06,0,.07.03.03.07l-.07.09c-.18.16-.34.36-.47.6-.2.35-.36.7-.48,1.05-.05.1-.1.22-.16.34-.03.13-.07.24-.13.34-.11.27-.25.57-.43.89-.06.15-.16.36-.31.65-.03.06-.08.18-.16.34-.06.15-.13.28-.23.4l-.05.16-.36.77-.24.59c-.13.31-.23.5-.28.59-.03.13-.1.26-.2.4-.11.23-.24.46-.41.7-.06.21-.12.35-.17.44l-.04.06-.16.31-.29.75-.24.59c-.03.06-.05.11-.08.15-.02.02-.05.04-.07.06,0,.04-.02.07-.04.09,0,.02-.03.07-.08.15-.18.33-.32.55-.41.67l-.11.18s-.02.06-.04.06l-.38.64c-.17.2-.27.42-.31.65l-.15.28-.24.53c-.07.1-.14.21-.19.34-.03.1-.07.2-.12.28-.05.06-.08.18-.09.35,0,.09.03.14.11.17.06.03.09.06.09.1.02.04.01.09-.01.13l-.12.28-.05.25c0,.09-.04.14-.11.15l-.27.11-.07.03c-.05.08-.13.13-.24.14-.09.01-.14.02-.16.02l-.23.08s-.11,0-.19.02c-.09.04-.16.04-.23.01l-.54-.11-.18-.11c-.33-.16-.56-.28-.71-.38-.06-.03-.11-.06-.15-.11-.02-.04-.05-.08-.09-.1-.13-.18-.26-.43-.39-.74-.11-.24-.21-.59-.3-1.02l-.19-.76-.05-.55c-.03-.13-.04-.25-.03-.36-.03-.17-.05-.45-.06-.84-.01-.13-.02-.31-.02-.55,0-.24,0-.45.02-.64-.01-.11-.01-.2,0-.29.03-.1.04-.21.03-.32l.04-.48c-.02-.22-.03-.38-.02-.48v-.83c.02-.17.02-.41,0-.71.01-.15.01-.37,0-.68,0-.06-.01-.12-.05-.16l-.07.12c-.1.16-.16.29-.19.37,0,.08-.04.18-.09.28-.05.08-.09.14-.11.18l-.19.37c-.07.12-.15.24-.22.37-.07.12-.14.23-.19.34-.18.35-.29.55-.34.61-.03.06-.09.15-.18.27,0,.06-.02.11-.04.12,0,.04-.07.15-.19.34,0,.04-.07.15-.19.34l-.45.8-.41.67-.39.77-.24.49c-.1.18-.17.3-.19.34l-.12.25c-.05.06-.1.15-.15.28-.03.08-.06.18-.09.28-.03.08-.07.17-.12.25-.14.35-.22.68-.25.97l-.04.48-.04.41c0,.19.08.45.22.76,0,.02,0,.03.03.03.02.02.03.05.03.07.02.02.03.06.02.1-.04,0-.06-.02-.06-.04-.02-.02-.05-.02-.1.02-.05.06-.1.06-.16-.01l-.15-.14ZM42.07,19.54s-.03-.01-.03-.03l.03-.29.03.07-.02.22s.03.03.03.03c-.02,0-.03,0-.03,0ZM42.2,19.55s-.03-.01-.03-.03l-.06-.1.04-.09h.03s.02.11.02.2v.03ZM42.16,19.22s-.05-.05-.1,0l.04-.12s.01-.03.03-.03c0,.02,0,.03,0,.03l.05.13s-.01.03-.03.03v-.03ZM41.88,18.4l.08-.22v-.03s0,.03,0,.03c0,.11-.03.18-.05.22h-.03ZM42.39,18.89s.03,0,.03-.03c.02-.02.04-.06.04-.12v-.03s-.03,0-.03.03c-.02.02-.04.06-.04.12v.03ZM42.94,16.62l-.06-.07-.08.15h.03s.1-.08.1-.08ZM42.32,15.19c.07-.12.12-.19.15-.21v-.03s0,.03,0,.03l-.12.25s-.03,0-.03.03v-.06ZM43.11,15.77c.09-.1.15-.24.17-.44h-.03s-.05.08-.07.12c-.02.02-.04.06-.04.12,0,.09-.02.15-.05.19v.03s.03-.03.03-.03ZM44.35,14.76s.03,0,.03-.03l.07-.12v-.03s-.03,0-.03,0c0,.02-.03.07-.08.15v.03ZM45.37,13.08h-.03s-.11.15-.11.15v.03s.03,0,.03,0l.11-.18ZM44.66,12.28c.05-.08.08-.13.08-.15v-.03s-.11.18-.11.18h.03ZM45.44,12.92s.03,0,.03-.03l.03-.03c.15-.29.28-.5.38-.64,0-.02.02-.06.04-.12.03-.06.05-.1.07-.12l.24-.49.19-.3v-.03s-.03,0-.03.03l-.15.21v.1s-.03.02-.08.06c-.25.45-.43.79-.54,1.01l-.19.34v.03ZM48.97,15.22l-.02-.1-.04.06.02.1.04-.06ZM49.22,14.15l-.06-.1s0-.03-.03-.03v.03s.02.13.02.13c.02,0,.03.01.03.03l.04-.06ZM46.62,10.81l.08-.19v-.03s-.11.18-.11.18v.03s.03,0,.03,0ZM49.12,13.89l.04-.06v-.03s0,0-.03,0c0,0,0,.01,0,.03l-.03.03s.06.07.06.07l-.03-.03ZM49.62,12.9v-.1s-.02,0-.02,0h-.03s-.04.12-.04.12h.03s.07-.02.07-.02ZM49.14,12.15v-.13s-.02-.03-.02-.03v.03s-.04.05-.04.09v.03s.03,0,.03,0h.03ZM48.8,10.93v-.1s.01-.03.01-.03h-.03c0,.06-.02.1-.04.12,0,.02.02.03.06.04v-.03ZM49.51,10.84l.03-.03v-.03s-.06,0-.06,0c0,0-.01,0-.03,0,0,0,0,.01,0,.03.02.02.03.06.02.1l.04-.06ZM49.49,10.38s0-.03,0-.03c.02,0,.03,0,.03,0l.04-.06s-.03-.02-.03-.07h-.03s.03.06.03.06c0,.02-.01.03-.03.03v.06ZM53.47,12.63l-.1.09.03.03.07-.12ZM48.98,6.55s0-.03,0-.03c.02,0,.03,0,.03,0l-.02-.1-.04.06.03.07ZM53.44,12.14c.03-.06.07-.1.14-.12l-.03-.03h-.03s-.1.08-.1.08c0,0,0,.01,0,.03,0,0-.01,0-.03,0l.06.04ZM53.64,12.13c.08,0,.12-.03.11-.12v-.03s-.02-.07-.02-.07l-.04.06s0,.05-.04.09l-.04.06h.03ZM53.79,11.53l-.03-.03-.1.09.06.07.07-.12ZM53.92,11.06s.03,0,.03-.03c.08,0,.13-.02.14-.08,0-.02,0-.03-.03-.03l-.03.03s-.03.05-.07.03l-.04.06v.03ZM54.48,10.56l.04-.06v-.06s-.06-.04-.06-.04v.03s.01.04,0,.06l-.04.06h.06ZM54.45,10.17l.12-.25h-.06s0,.03,0,.03c.02,0,.03.02.03.07-.05.04-.07.07-.07.09v.1s0-.03,0-.03ZM54.64,10.16s.03,0,.03-.03l.07-.12v-.03s-.03,0-.03,0l-.11.12.03.07ZM54.73,9.91s.06-.02.1-.06c0,0-.01,0-.03,0t0,0s-.07.02-.07.06ZM54.9,9.79v-.06s-.06.03-.06.03h-.03s-.01.03-.03.03l.06.04.07-.03ZM54.92,9.54v.03s.06,0,.06-.03c0-.02-.02-.05-.06-.1l-.07.12.07-.03ZM54.99,9.48s0-.03,0-.03c.02,0,.03,0,.03,0v-.03s0-.02,0-.06h-.06s.03.06.03.06v.06ZM54.91,9.28l.04-.12v-.03s-.03,0-.03,0l-.04.12v.03s.03,0,.03,0ZM55.11,9.3s0-.04,0-.06c.03-.04.06-.08.11-.12l-.06-.1h-.03s0,.09,0,.09v.03s-.04.05-.04.09c0,.02-.01.04-.04.06v.03s.06-.03.06-.03ZM55.26,8.96s-.02-.04,0-.06c.04-.02.07-.04.07-.06v-.06s-.06.03-.06.03l-.04.09-.07.06h.1ZM55.5,8.5s.01-.03.03-.03h-.06s-.01,0-.03,0c0,0,0,.01,0,.03l.03.07.04-.06ZM55.62,8.12s.07-.08.07-.12l-.1.09s0,.03.03.03ZM55.76,8.1s.06,0,.07-.03c0-.02,0-.03-.03-.03l-.07.03s0,.03,0,.03c.02,0,.03,0,.03,0ZM56.06,7.58s.02-.07.04-.09h-.03s-.04.09-.04.09v.03s.03-.03.03-.03ZM56.4,6.65s.02-.02.07-.06l.16-.34v-.06s0-.03,0-.03c-.02.02-.06.03-.1.02l-.03.03s.06.07.06.07c0,.02-.01.03-.03.03-.02,0-.03,0-.03.03,0,.11-.04.18-.08.22v.1ZM56.45,5.66c.07-.06.1-.09.1-.09l-.06-.04s-.03.05-.07.09l.03.03ZM56.6,5.41s0-.03-.03-.03l-.04.06.03.07.04-.09ZM56.71,5.26l-.06-.04-.03.03s0,.01,0,.03c0,0,.01,0,.03,0l.07-.03ZM57.59,4.73l.1-.09-.04.12-.03.03-.03-.07ZM58.1,5.16s.03-.05.07-.09l-.03-.03s-.07.02-.07.06l.03.07ZM57.69,4.64c0-.06-.01-.09-.06-.07,0-.02.03-.05.07-.09h.03s.02-.03.07-.02c0,.04-.02.07-.04.09,0,.02-.03.05-.07.09ZM57.87,4.11l.07-.12.03.03-.11.12v-.03ZM56.6,21.99s-.12-.1-.24-.15c-.02.04-.06.04-.1,0-.15-.06-.22-.13-.24-.21l-.08-.2-.05-.13v-.06s0-.08-.02-.1h-.03s-.01-.08-.05-.17c0-.02,0-.05-.02-.1,0-.02.02-.06.04-.12.02-.02.02-.08-.02-.19-.02-.04-.05-.05-.1,0v.03s-.03-.01-.03-.03c.01-.13,0-.22,0-.29,0-.02-.02-.05-.06-.1v-.06s.03.03.03.03h.03c0-.06,0-.09-.02-.1-.02,0-.03-.01-.03-.03,0-.06.02-.11.04-.12,0-.02,0-.05,0-.1v-.03s-.03.03-.03.03v.06s-.04,0-.04,0c-.02-.02-.03-.07-.02-.13-.02-.04-.01-.08,0-.1,0-.02,0-.04,0-.06h.03s.07-.07.07-.09c0-.02-.02-.06-.06-.1-.02-.04-.02-.11-.02-.19,0-.09.04-.18.09-.28.03-.1.05-.18.05-.22.03-.04.05-.09.08-.15.03-.06.06-.12.11-.18.05-.12.08-.2.08-.22v-.03s0,0-.03,0c0,0,0,.01,0,.03l-.11.21c-.05.08-.08.14-.08.19l-.07.03v-.06s.04-.1.09-.19c0-.06.03-.14.08-.22.03-.08.06-.16.08-.22.03-.06.05-.12.08-.19l.12-.28s.02,0,0,0c0-.02,0-.03,0-.03v-.06s.04-.1.09-.19v-.03s-.03,0-.03,0l-.04.06-.03.03v-.03s0,0-.03,0c0,0,0-.01,0-.03v.03s-.12.18-.12.18l-.03.03v-.03c.01-.09.03-.15.05-.19,0-.06.02-.11.04-.12.03-.04.05-.08.07-.12l.02-.19h-.03s-.03,0-.03.03l-.07.03s-.01,0-.03,0c0-.02.01-.03.03-.03,0-.09.03-.14.08-.15v-.03c.03-.08.07-.18.12-.28.05-.1.09-.17.12-.21.05-.08.08-.14.08-.19.02-.02.02-.03,0-.03,0-.02,0-.04,0-.06-.04,0-.06,0-.07.03,0,0-.02.02-.07.06v-.1s.08-.12.08-.12v-.03s-.03,0-.03,0c0,.04-.03.08-.07.12v.03s-.01-.03-.03-.03l.04-.12v-.03s-.03,0-.03.03c-.05.04-.07.09-.08.15-.02,0-.03,0-.03.03h.06s0,.02,0,.04c0,0,.01,0,.03,0-.02,0-.03,0-.03.03-.06-.03-.1,0-.1.09l-.29.39v-.03s.12-.25.12-.25c.1-.18.19-.37.27-.55l.23-.43.04-.06s-.06,0-.07.03l-.11.18-.04.06s.02-.06.04-.06l.35-.64c.12-.18.29-.48.49-.89l.26-.46c.08-.14.17-.3.26-.46.1-.18.19-.38.28-.59.03-.13.07-.23.12-.31.05-.08.09-.15.12-.21.15-.29.26-.5.31-.65l.36-.77.27-.55c.11-.25.18-.43.21-.56l.11-.15c.16-.31.27-.58.36-.8.03-.08.09-.21.19-.37l.35-1.03.26-.46.12-.28.11-.18.07-.06c0-.06.04-.16.09-.28l.22-.27s.04-.05.04-.09c.05-.04.08-.06.1-.06.06,0,.14,0,.23-.04v-.03c.03-.06.05-.15.06-.25,0-.06.06-.11.17-.15.04,0,.08,0,.1-.02.02-.02.05-.04.07-.06,0-.02.03-.05.07-.09,0-.02.01-.03.03-.03v-.1s.07-.03.07-.03l-.03.03.03.07s.03,0,.03,0c0-.02,0-.03,0-.03.04,0,.06.02.06.04h.03s.03,0,.03,0v.03s-.11.15-.11.15v.1s.03-.06.03-.06c0-.02.06-.05.17-.08.02,0,.06,0,.13.01.09-.01.15-.05.2-.11l.03-.03.03.07s0,.08.02.1c.05-.04.07-.06.07-.06.02-.02.11-.12.25-.3.09-.04.15-.07.17-.11,0,0,.01,0,.03,0,.02,0,.03.01.03.03.02.07.07.08.16.05,0-.02.01-.03.03-.03l-.04.06s-.01.04-.04.06c-.02.02-.02.04,0,.06.02.02.06.04.12.04.08,0,.12-.03.11-.12,0-.04.03-.06.07-.06.06,0,.12-.01.16-.05.04-.02.1-.02.16-.02.06,0,.12.02.16.05,0,0,.02.02.06.07.02.04,0,.1-.05.16-.03.04-.04.07-.04.09,0,.04,0,.06.03.07v.03s-.14.08-.14.08v.06c.09.09.13.26.11.49l-.02.26c-.01.17-.08.4-.19.69-.03.15-.06.37-.09.67l-.02.19c-.02.26-.01.53.02.84.03.15.05.4.06.74.01.09,0,.17-.02.26,0,.09,0,.17,0,.26,0,.11,0,.27.02.48,0,.3.02.68.06,1.13l.05.87.04.68c.02.3.02.54,0,.71.01.34.01.6,0,.77,0,.02,0,.03.03.03-.01.13,0,.3.02.52l.05.16c.04.07.06.24.08.52,0,.04,0,.11-.02.19.02.07,0,.13-.05.19l.03.07.07-.03.19-.37.26-.46.22-.33.15-.24.25-.33.19-.3.12-.25s.09-.15.19-.34l.34-.61c.03-.06.05-.11.08-.15.03-.06.05-.11.08-.15l.15-.28.38-.71.16-.37.34-.61.3-.55.35-.68.49-.82c.05-.1.1-.19.15-.28.07-.08.12-.15.15-.21.1-.14.22-.36.38-.64l.34-.61.1-.09-.04.09-.2.4-.04.06c-.07.04-.13.14-.19.3,0,.02-.03.07-.08.15-.03.08-.09.21-.19.37-.05.08-.1.14-.14.18,0,0,0,.01,0,.03,0,0,.01,0,.03,0h.03s.08-.21.08-.21v.13s-.02.1-.02.1c-.02.02-.04.04-.04.06.02.02.05.03.1,0,.04-.02.06,0,.06.07-.02-.02-.04-.02-.06,0-.02.02-.03.03-.03.03v.06s.02.03.02.03c.07-.06.09-.1.07-.12.09-.04.13-.1.11-.18,0,0,0-.01-.03-.03,0-.04.03-.06.07-.06,0-.06.03-.09.07-.09.02,0,.03-.02.04-.06-.04-.05-.03-.07.04-.06v-.03s-.03-.03-.03-.03c.02-.02.04-.04.04-.06l.16-.34.11-.18s.07-.09.15-.21l.04-.06.09.04h.03s.03-.04,0-.06h-.03s-.1.02-.1.02l.08-.15.07-.03h.03s.05.05.1.01l.11-.15s.02-.06.04-.06l.04-.06v.06s-.16.34-.16.34l-.04.06s-.06.07-.04.09c-.02.02-.04.05-.04.09.02.02.02.04,0,.06v.03s-.01,0-.03,0c0,0,0-.01,0-.03v-.03s0-.03,0-.03v.03s-.08.12-.08.12c-.05.04-.04.07.02.1v.06c-.06.08-.08.15-.09.22,0,0-.01.02-.04.06,0,.02.02.03.06.04v.1s-.04,0-.04.03h.06s.11-.15.11-.15c.07-.08.16-.22.26-.43l.12-.25s0-.03,0-.03c.02,0,.03,0,.03,0v.03c-.1.14-.17.29-.2.43v.03s.03,0,.03-.03l.16-.31s.09-.13.18-.27c0-.02,0-.03,0-.03.02-.02.03-.04,0-.06,0-.02.01-.03.03-.03.02-.02.04-.05.04-.09l.03.03s-.04.04-.04.06c.02.02.02.04,0,.06-.02.02-.04.09-.05.22l.07-.03.12-.21s.09-.06.13-.05l.07-.03.04-.06-.03.03-.07.03s.02-.06.04-.06c0-.02.03-.05.07-.09h.03s.08-.15.08-.15c.02,0,.03,0,.03,0,0-.02,0-.03,0-.03.08,0,.13-.05.14-.18,0-.02.01-.03.03-.03.04-.02.08-.01.1,0,.08.05.14.07.19.05h.06s-.01.04-.03.03l-.28.26-.19.34s-.03,0-.03.03c.02,0,.03,0,.03-.03.04-.02.09-.07.14-.15l.11-.15c.03-.08.11-.15.24-.2.04-.02.09-.07.14-.15l.1-.09h.06s0,.1,0,.1l-.03.03h.03s.07-.01.07-.06c-.02-.02-.02-.03,0-.03.02-.02.05-.03.07-.03.06,0,.12-.04.17-.15,0,0,.09-.08.28-.23v.03s-.15.21-.15.21c-.03.06-.03.13-.02.19.04.05.07.07.09.07.06,0,.07.03.03.07l-.07.09c-.18.16-.34.36-.47.6-.2.35-.36.7-.48,1.05-.05.1-.1.22-.16.34-.03.13-.07.24-.13.34-.11.27-.25.57-.43.89-.06.15-.16.36-.31.65-.03.06-.08.18-.16.34-.06.15-.13.28-.23.4l-.05.16-.36.77-.24.59c-.13.31-.23.51-.28.59-.03.13-.1.26-.2.4-.11.23-.24.46-.41.7-.06.21-.12.35-.17.44l-.04.06-.16.31-.29.75-.24.59c-.03.06-.05.11-.08.15-.02.02-.05.04-.07.06,0,.04-.02.07-.04.09,0,.02-.03.07-.08.15-.18.33-.32.55-.41.67l-.11.18s-.02.06-.04.06l-.38.64c-.17.2-.27.42-.31.65l-.15.28-.24.53c-.07.1-.14.21-.19.34-.03.1-.07.2-.12.28-.05.06-.08.18-.09.35,0,.09.03.14.11.17.06.03.09.06.09.1.02.04.01.09-.01.13l-.12.28-.05.25c0,.09-.04.14-.11.15l-.27.11-.07.03c-.05.08-.13.13-.24.14-.09.01-.14.02-.16.02l-.23.08s-.11,0-.19.02c-.09.04-.16.04-.23.01l-.54-.11-.18-.11c-.33-.16-.56-.28-.71-.38-.06-.03-.11-.06-.15-.11-.02-.04-.05-.08-.09-.1-.13-.18-.26-.43-.39-.74-.11-.24-.21-.59-.3-1.02l-.19-.76-.05-.55c-.03-.13-.04-.25-.03-.36-.03-.17-.05-.45-.06-.84-.01-.13-.02-.31-.02-.55,0-.24,0-.45.02-.64-.01-.11-.01-.2,0-.29.03-.1.04-.21.03-.32l.04-.48c-.02-.22-.03-.38-.02-.48v-.83c.02-.17.02-.41,0-.71.01-.15.01-.37,0-.68,0-.06-.01-.12-.05-.16l-.07.12c-.1.16-.16.29-.19.37,0,.09-.04.18-.09.28-.05.08-.09.14-.11.18l-.19.37c-.07.12-.15.24-.22.37-.07.12-.14.23-.19.34-.18.35-.29.55-.34.61-.03.06-.09.15-.18.27,0,.06-.02.11-.04.12,0,.04-.07.15-.19.34,0,.04-.07.15-.19.34l-.45.8-.41.67-.39.77-.24.49c-.1.18-.17.3-.19.34l-.12.25c-.05.06-.1.15-.15.28-.03.08-.06.18-.09.28-.03.08-.07.17-.12.25-.14.35-.22.68-.25.97l-.04.48-.04.41c0,.19.08.45.22.76,0,.02,0,.03.03.03.02.02.03.05.03.07.02.02.03.06.02.1-.04,0-.06-.02-.06-.04-.02-.02-.05-.02-.1.02-.05.06-.1.06-.16-.01l-.15-.14ZM55.4,20.69s-.03-.01-.03-.03l.03-.29.03.07-.02.22s.03.03.03.03c-.02,0-.03,0-.03,0ZM55.53,20.71s-.03-.01-.03-.03l-.06-.1.04-.09h.03s.02.11.02.2v.03ZM55.49,20.38s-.05-.05-.1,0l.04-.12s.01-.03.03-.03c0,.02,0,.03,0,.03l.05.13s-.01.03-.03.03v-.03ZM55.21,19.55l.08-.22v-.03s0,.03,0,.03c0,.11-.03.18-.05.22h-.03ZM55.71,20.05s.03,0,.03-.03c.02-.02.04-.06.04-.12v-.03s-.03,0-.03.03c-.02.02-.04.06-.04.12v.03ZM56.26,17.78l-.06-.07-.08.15h.03s.1-.08.1-.08ZM55.65,16.35c.07-.12.12-.19.15-.21v-.03s0,.03,0,.03l-.12.25s-.03,0-.03.03v-.06ZM56.43,16.93c.09-.1.15-.24.17-.44h-.03s-.05.08-.07.12c-.02.02-.04.06-.04.12,0,.09-.02.15-.05.19v.03s.03-.03.03-.03ZM57.68,15.91s.03,0,.03-.03l.07-.12v-.03s-.03,0-.03,0c0,.02-.03.07-.08.15v.03ZM58.69,14.24h-.03s-.11.15-.11.15v.03s.03,0,.03,0l.11-.18ZM57.99,13.44c.05-.08.08-.13.08-.15v-.03s-.11.18-.11.18h.03ZM58.77,14.08s.03,0,.03-.03l.03-.03c.15-.29.28-.5.38-.64,0-.02.02-.06.04-.12.03-.06.05-.1.07-.12l.24-.49.19-.31v-.03s-.03,0-.03.03l-.15.21v.1s-.03.02-.08.06c-.25.45-.43.79-.54,1.01l-.19.34v.03ZM62.29,16.38l-.02-.1-.04.06.02.1.04-.06ZM62.55,15.31l-.06-.1s0-.03-.03-.03v.03s.02.13.02.13c.02,0,.03.01.03.03l.04-.06ZM59.95,11.97l.08-.19v-.03s-.11.18-.11.18v.03s.03,0,.03,0ZM62.44,15.04l.04-.06v-.03s0,0-.03,0c0,0,0,.01,0,.03l-.03.03s.06.07.06.07l-.03-.03ZM62.95,14.06v-.1s-.02,0-.02,0h-.03s-.04.12-.04.12h.03s.07-.02.07-.02ZM62.46,13.31v-.13s-.02-.03-.02-.03v.03s-.04.05-.04.09v.03s.03,0,.03,0h.03ZM62.12,12.09v-.1s.01-.03.01-.03h-.03c0,.06-.02.1-.04.12,0,.02.02.03.06.04v-.03ZM62.84,11.99l.03-.03v-.03s-.06,0-.06,0c0,0-.01,0-.03,0,0,0,0,.01,0,.03.02.02.03.06.02.1l.04-.06ZM62.81,11.54s0-.03,0-.03c.02,0,.03,0,.03,0l.04-.06s-.03-.02-.03-.07h-.03s.03.06.03.06c0,.02-.01.03-.03.03v.06ZM66.79,13.78l-.1.09.03.03.07-.12ZM62.31,7.71s0-.03,0-.03c.02,0,.03,0,.03,0l-.02-.1-.04.06.03.07ZM66.77,13.3c.03-.06.07-.1.14-.12l-.03-.03h-.03s-.1.08-.1.08c0,0,0,.01,0,.03,0,0-.01,0-.03,0l.06.04ZM66.96,13.28c.08,0,.12-.03.11-.12v-.03s-.02-.07-.02-.07l-.04.06s0,.05-.04.09l-.04.06h.03ZM67.11,12.69l-.03-.03-.1.09.06.07.07-.12ZM67.25,12.22s.03,0,.03-.03c.08,0,.13-.02.14-.08,0-.02,0-.03-.03-.03l-.03.03s-.03.05-.07.03l-.04.06v.03ZM67.81,11.72l.04-.06v-.06s-.06-.04-.06-.04v.03s.01.04,0,.06l-.04.06h.06ZM67.78,11.33l.12-.25h-.06s0,.03,0,.03c.02,0,.03.02.03.07-.05.04-.07.07-.07.09v.1s0-.03,0-.03ZM67.97,11.32s.03,0,.03-.03l.07-.12v-.03s-.03,0-.03,0l-.11.12.03.07ZM68.06,11.07s.06-.02.1-.06c0,0-.01,0-.03,0t0,0s-.07.02-.07.06ZM68.23,10.95v-.06s-.06.03-.06.03h-.03s-.01.03-.03.03l.06.04.07-.03ZM68.25,10.7v.03s.06,0,.06-.03c0-.02-.02-.06-.06-.1l-.07.12.07-.03ZM68.32,10.64s0-.03,0-.03c.02,0,.03,0,.03,0v-.03s0-.02,0-.06h-.06s.03.06.03.06v.06ZM68.24,10.44l.04-.12v-.03s-.03,0-.03,0l-.04.12v.03s.03,0,.03,0ZM68.43,10.46s0-.04,0-.06c.03-.04.06-.08.11-.12l-.06-.1h-.03s0,.09,0,.09v.03s-.04.05-.04.09c0,.02-.01.04-.04.06v.03s.06-.03.06-.03ZM68.59,10.12s-.02-.04,0-.06c.04-.02.07-.04.07-.06v-.06s-.06.03-.06.03l-.04.09-.07.06h.1ZM68.82,9.66s.01-.03.03-.03h-.06s-.01,0-.03,0c0,0,0,.01,0,.03l.03.07.04-.06ZM68.95,9.28s.07-.08.07-.12l-.1.09s0,.03.03.03ZM69.08,9.26s.06,0,.07-.03c0-.02,0-.03-.03-.03l-.07.03s0,.03,0,.03c.02,0,.03,0,.03,0ZM69.38,8.74s.02-.07.04-.09h-.03s-.04.09-.04.09v.03s.03-.03.03-.03ZM69.72,7.81s.02-.02.07-.06l.16-.34v-.06s0-.03,0-.03c-.02.02-.06.03-.1.02l-.03.03s.06.07.06.07c0,.02-.01.03-.03.03-.02,0-.03,0-.03.03,0,.11-.04.18-.08.22v.1ZM69.77,6.82c.07-.06.1-.09.1-.09l-.06-.04s-.03.05-.07.09l.03.03ZM69.92,6.57s0-.03-.03-.03l-.04.06.03.07.04-.09ZM70.03,6.42l-.06-.04-.03.03s0,.01,0,.03c0,0,.01,0,.03,0l.07-.03ZM70.92,5.89l.1-.09-.04.12-.03.03-.03-.07ZM71.42,6.32s.03-.05.07-.09l-.03-.03s-.07.02-.07.06l.03.07ZM71.02,5.8c0-.06-.01-.09-.06-.07,0-.02.03-.05.07-.09h.03s.02-.03.07-.02c0,.04-.02.07-.04.09,0,.02-.03.05-.07.09ZM71.19,5.27l.07-.12.03.03-.11.12v-.03ZM72.8,22.43c-.11,0-.2-.06-.28-.15l-.12-.04c-.15-.01-.27-.08-.37-.19-.08-.03-.15-.08-.21-.15-.08-.07-.18-.11-.31-.12-.02.02-.07.02-.13-.01-.06-.03-.11-.04-.16-.05l-.4-.23c-.13-.2-.29-.36-.47-.46-.12-.07-.21-.12-.28-.12-.11,0-.18-.08-.21-.21-.04-.07-.16-.15-.36-.26-.16-.08-.34-.28-.53-.59-.04-.07-.12-.3-.26-.7-.03-.13-.03-.25,0-.35h-.03s.13-.35.13-.35c.06-.17.09-.28.09-.35l.09-.25s.08-.1.11-.18c.03-.08.04-.14.05-.16-.06-.07-.07-.12-.05-.16.05-.06.07-.1.07-.12.03-.15.1-.27.19-.37.08-.16.16-.36.24-.59.03-.1.11-.26.23-.46.05-.08.2-.34.45-.76.08-.21.16-.37.24-.49.08-.14.14-.27.19-.37.12-.16.23-.35.34-.58.12-.1.18-.23.2-.4l.04-.12.11-.21s.04,0,.07-.03c.02-.02.04-.04.04-.06l.07-.09c.2-.33.31-.53.34-.61.1-.14.18-.27.26-.39.08-.14.14-.26.19-.34l.3-.49c.03-.06.08-.18.16-.34.08-.16.17-.31.26-.43.12-.18.2-.34.23-.46l.24-.49c.07-.08.12-.15.15-.21.03-.08.06-.15.08-.19,0-.06.05-.16.12-.28.04-.02.06-.05.04-.09,0-.06,0-.11-.02-.13l-.18-.14s0-.04-.03-.07c0-.04.02-.07.04-.09,0-.11,0-.18-.04-.23v-.06s.02-.13.02-.13c-.03-.15.02-.23.15-.24.05-.04.12-.07.23-.11.26-.08.49-.2.67-.36.04,0,.07-.03.07-.09l.32-.71s.03-.08.01-.13c0-.04.02-.09.05-.16.02-.04.06-.11.11-.21.07-.12.16-.2.25-.24.16-.14.36-.19.59-.17.21.02.37.04.48.07.1.03.21.1.3.22.06.03.12.06.18.11.06.05.12.09.18.11.02.04.07.09.15.14.1.05.17.09.21.12l.27.25s.09.07.15.08c.22-.05.39-.1.53-.18.46-.17.9-.31,1.32-.4.31-.14.62-.25.93-.3.29-.08.51-.12.68-.1l.22.02.29.02s.07.02.16.05c.08,0,.15.04.18.11.02.02.05.04.09.04.04,0,.08.02.12.04.02.02.05.04.09.04.02,0,.03.01.03.03h-.03s-.04,0-.07.02c0,.02,0,.03,0,.03l.03.07-.03.03.02.1.22.05.06.07s.04.06.06.1c.02.02.04.07.05.13,0,.06.01.11.05.13.04.02.07.05.09.07.02,0,.05.06.08.17.04.02.07.05.09.07.04.02.07.05.09.07.08.09.09.19.04.29-.01.13-.03.22-.06.28l.02.19c.01.09,0,.17-.02.26l-.13.37-.12.21h-.06c-.04-.05-.03-.12.02-.2.02-.02.04-.05.04-.09,0-.06,0-.11-.02-.13-.02-.04-.04-.09-.05-.13-.02-.04-.07-.07-.15-.08-.02,0-.03.02-.04.06l-.04.06v-.06s-.02-.07-.02-.13l-.19-.02h-.1c-.06-.04-.15-.04-.25-.03-.31.1-.54.17-.69.2-.26.08-.66.2-1.19.35-.44.09-.75.17-.95.24-.11.03-.27.08-.49.15-.22.05-.4.07-.55.08-.07.02-.14.04-.23.08-.07.02-.14.04-.23.08-.13.03-.2.05-.2.05-.13.03-.24.04-.32.04-.02.02-.07.04-.13.05-.06,0-.1,0-.1.02l-.08.15-.31.62c-.05.08-.12.19-.22.33-.07.12-.14.24-.19.37-.12.2-.21.37-.27.49-.07.12-.16.24-.26.36-.07.12-.15.25-.23.4l-.11.15v.03s.06,0,.06,0l.4-.13c.13-.01.25,0,.35.03.04.02.17.05.38.07.06,0,.1.04.12.11.02.02.05.04.09.04.19.08.3.12.34.13v.06s-.04,0-.04,0c-.02,0-.03,0-.03.03,0,.02-.01.03-.03.03.02,0,.03.01.03.03,0,.02,0,.03.03.03l.22.05h.03s.12.11.12.11l-.13.05c-.09,0-.14,0-.16.02h-.03s0,.03.03.03l.09.04.32.03s.1.03.19.08c.03.11.08.18.14.21l.19.05c.06.03.09.06.09.1,0,.02-.01.03-.03.03l-.25-.09h-.06s.03,0,.03.03c.02.07.05.12.11.17.08.03.14.06.19.08l.26.28s0,.01,0,.03c0,0,.01,0,.03,0h-.1s0-.04-.03-.04c-.02,0-.03,0-.03,0-.01-.09-.03-.11-.06-.07-.02.02-.05.03-.07.03l.02.13.15.14s0,.01,0,.03c.02.02.04.04.06.04-.04,0-.08-.03-.12-.07h-.03s-.02,0-.06,0l.02.1c.17.06.28.12.34.19l.14.24.06.07s.04.06,0,.1c-.02.02-.06.03-.1.02l-.18-.11-.28-.12c-.08-.05-.11-.02-.07.09v.03s-.03-.03-.03-.03c-.02-.04-.07-.06-.16-.05l-.98.14-.91.15-.26.07c-.33.06-.64.1-.94.14-.11.01-.22.03-.33.07-.11.01-.24.02-.39.03-.04,0-.12.01-.23.04-.11.01-.22.01-.32,0l-.1.06c-.13.29-.23.47-.3.55l-.14.15c-.15.24-.31.53-.49.86-.07.12-.15.27-.23.43-.06.15-.14.3-.26.46-.26.58-.43.95-.48,1.11-.03.08-.06.18-.09.28-.03.08-.05.19-.06.32-.03.08,0,.12.09.1.07-.04.12-.05.17-.05.07-.02.11-.02.13-.02h.03s-.03.01-.03.03l-.33.13s-.04,0-.07.03c0,0-.01,0-.03,0h.13s.26,0,.26,0h.06s-.03.03-.03.03l-.3.07c-.07.02-.11.04-.14.08-.02.02-.03.06-.01.13,0,.02,0,.04,0,.06.02,0,.03.01.03.03,0,.04.04.07.12.07h.26c.07-.03.14-.04.23-.05.11-.03.22-.05.32-.04h.06s.04,0,.06.01c.04,0,.07.02.09.04.08.09.15.12.22.08l1.02-.23.43-.12h.06s.11,0,.2-.04c.09-.04.18-.06.26-.07.04-.02.11-.04.2-.08.11-.05.22-.09.33-.1.02,0,.16-.04.43-.12.13-.03.23-.07.3-.1.09-.04.17-.06.23-.08.17,0,.26-.02.26-.04l.04-.06s.03.01.03.03c0,.02,0,.03,0,.03.07-.06.1-.04.09.04.02.02.04.04.06.04.04,0,.06,0,.07-.03h.03s.06,0,.06,0v-.03s0-.06,0-.06c0-.02.01-.03.03-.03v.03s-.01.1-.01.1c0,0-.02.02-.07.06v.06s0,.04-.01.06c.02,0,.03.01.03.03.02.02.08.07.18.14.02,0,.03.01.03.03.07.18.14.27.2.27.02,0,.03,0,.03-.03.02-.02.05-.03.07-.03l.03-.03s0,.01,0,.03c.02,0,.04,0,.06,0v.03s-.01.13-.01.13c.02,0,.06-.02.1-.06.05-.04.07-.07.07-.09,0,0,0-.01,0-.03.02-.02.04-.04.04-.06.02,0,.03.01.03.03,0,.02,0,.03.03.03v.03s-.06.09-.05.16c.02.02.03.07.02.13.03.11.09.15.18.11.07-.02.12-.01.16.01.06.09.05.2-.03.32-.09.06-.13.13-.12.21.01.09.02.14.02.16l-.03.32-.03.03s-.01,0-.03,0c-.02,0-.03-.01-.03-.03-.06-.03-.1-.07-.12-.14-.02-.04-.04-.06-.06-.04-.1.12-.25.19-.47.22-.11.03-.24.06-.39.09-.13.03-.27.07-.43.12-.13.03-.27.08-.43.16h-.03s-.08-.02-.13.02c-.05.04-.08.06-.1.06l-.03.03h-.13c-.03.05-.07.09-.14.11-.07.02-.11.02-.13.02l-.19.02c-.13.03-.23.11-.31.23h-.03c-.06,0-.15,0-.26.04-.11.03-.2.06-.26.07l-.27.11s-.06.02-.1.06c-.06,0-.1,0-.1,0h-.06c-.06-.01-.14,0-.23.04-.09.06-.17.09-.23.11l-.14.08-.23.08h-.1ZM72.08,19.96l.07-.06h-.06c-.06-.01-.11,0-.13.05l-.03.03h.06s.1-.02.1-.02ZM70.44,17.38l.04-.12s0-.03-.03-.03v.03s-.04.06-.05.12h.03ZM72.38,19.86c.11,0,.18,0,.23-.01h.03s-.03-.03-.03-.03l-.23.04h-.03s0,0,0,.03c.02,0,.03,0,.03-.03ZM70.64,16.91s.07-.09.08-.15v-.03s-.03,0-.03,0l-.07.12v.06s.03,0,.03,0ZM74.78,20.65s.05-.06.07-.06c.02,0,.04,0,.07-.03l.36-.13c.06,0,.14,0,.23-.04l.04-.06-.07.03c-.22.02-.38.06-.49.12-.05.04-.11.08-.2.11-.02,0-.03.02-.04.06h.03ZM74.84,20.04c.13-.05.27-.09.4-.13.13-.03.24-.06.33-.1l.07-.03s-.06,0-.06,0l-.43.09s-.1.04-.17.08c-.04.02-.1.04-.17.08h-.03s.03,0,.03,0h.03ZM75.96,19.62c.15-.03.27-.07.36-.13h.13s-.16-.03-.16-.03c-.13.07-.25.12-.33.13,0,0,0,.01,0,.03,0,0-.01,0-.03,0h.03ZM82.85,8.08v-.06c.01-.06.03-.11.05-.12h.03s-.05.22-.05.22h-.03s0-.03,0-.03ZM2.06,40.92c-.12-.1-.22-.14-.31-.12-.07.02-.12.01-.16-.01-.04,0-.09,0-.13-.01-.13-.01-.21-.05-.25-.12-.02,0-.04-.02-.06-.07-.04-.03-.08-.03-.13-.01-.04-.05-.09-.09-.15-.14-.08-.03-.13-.07-.15-.11,0-.02,0-.03,0-.03-.02,0-.03,0-.03,0-.13-.03-.24-.13-.33-.29l-.17-.27-.2-.27v-.13s.05.02.07,0c0,0,0,.01,0,.03l.25.12h.03s0,0,0-.03c0,0-.01,0-.03,0l-.27-.18v-.03s.07,0,.07-.03c0-.02,0-.03-.03-.03-.04-.05-.04-.09.01-.13.02-.04.04-.07.04-.09l.03-.03s.05,0,.1,0c.04,0,.07.03.09.07,0,.02,0,.03.03.03v-.03s-.07-.07-.09-.07c-.02,0-.04,0-.06,0-.02-.02-.02-.06,0-.1v-.03s-.06-.07-.05-.13c0-.06.02-.11.04-.12.04,0,.06,0,.07-.03,0-.04,0-.08.01-.13-.02-.07-.01-.12.01-.16l.18-.56s.07-.15.2-.4l.2-.5.3-.55.38-.71.26-.43c.03-.06.05-.12.08-.19.03-.08.07-.17.12-.25l.11-.12.3-.52.15-.28c.04-.17.12-.34.24-.53.1-.18.18-.33.23-.43l.11-.18c.1-.21.19-.36.26-.46.13-.27.26-.49.38-.67.07-.1.13-.21.16-.34.06-.21.14-.38.24-.53.07-.08.15-.19.22-.33.08-.14.14-.26.19-.34l.23-.4c.1-.21.19-.36.26-.46.1-.16.19-.28.26-.36v-.03s.19-.31.19-.31l.15-.21c.03-.08.09-.18.19-.31.05-.08.09-.16.12-.25.05-.08.11-.17.18-.27.15-.2.24-.35.3-.46.35-.53.59-.92.75-1.19.25-.36.42-.65.52-.85.15-.2.25-.36.3-.49.12-.2.2-.4.21-.59,0-.06.04-.16.09-.28.03-.1.12-.21.25-.33l.32-.36c.07-.08.2-.18.38-.29.12-.1.33-.15.66-.17.17.01.3.04.38.07.04.02.08.04.12.04.07-.02.12-.01.16.01.4.08.7.23.89.46l.23.31.12.11.03.07s-.07.19-.14.5l-.05.19-.05.16c-.01.13.08.21.27.25.09,0,.15.03.19.08v.03s-.03,0-.03,0l-.19-.02c-.09.04-.15.07-.17.11l-.25.33s0,.01,0,.03c0,0-.01,0-.03,0-.11.05-.15.15-.12.28l-.04.09s-.03.05-.07.09c0,.06-.02.09-.04.09-.02.02-.04.02-.06,0s-.04-.04-.06-.04c-.06,0-.12.01-.16.05l-.33.42c-.15.2-.24.36-.27.49-.02.21-.14.45-.35.71l-.44.67-.29.39-.07.09s-.03.07-.08.15c-.02.04-.06.1-.11.18-.05.06-.1.13-.15.21-.1.21-.19.36-.26.46-.07.1-.15.22-.22.37-.06.15-.1.26-.13.34l-.24.53h.03s.18-.21.18-.21c.21-.24.32-.36.32-.36.18-.16.48-.24.89-.24.17.01.3.02.39,0h.03s.09.04.09.04c-.02.02-.06.03-.1.02l-.52.05c-.3.02-.55.11-.73.29-.14.12-.25.26-.33.42-.16.31-.32.53-.51.66,0,0-.13.11-.38.32-.14.12-.29.3-.46.54-.15.2-.25.36-.3.49-.2.33-.34.57-.42.73-.05.08-.11.17-.18.27-.05.08-.11.18-.19.3-.05.06-.1.14-.15.24-.05.1-.1.17-.15.21-.1.12-.22.32-.37.61,0,0-.02.02-.07.06,0,.04-.03.08-.07.12l-.2.4-.24.49-.11.15-.07.12s0,.08.02.1c0-.02.01-.03.03-.03.02,0,.03,0,.03-.03l.25-.3s.02-.02.07-.06v.1s-.38.55-.38.55l-.34.61c-.03.06-.03.12-.01.16.02.02.06.03.13.01.06,0,.13,0,.19-.02.07-.02.13-.02.19-.02.11-.01.24-.03.39-.06.15-.05.29-.08.39-.09l.33-.13.17-.11.07-.03c.13.01.2-.01.23-.08,0-.02,0-.03,0-.03.02,0,.03,0,.03,0v.03s-.14.15-.14.15c-.05.04-.05.06,0,.06.02,0,.03.02.03.07.02.02.04.02.06,0l.36-.1h.03s.04,0,.06,0c.02-.02.03-.05,0-.1l.04-.06.07-.03c.06,0,.08.02.06.04l.03.03.03-.03s0-.07.07-.09l.26-.07h.13s0,.02.03.05c.04,0,.07-.02.07-.06l.03-.03s.05.04.09.04c.04-.02.08-.01.1,0l.07-.03c.07-.06.1-.09.1-.09.02-.02.05-.03.07-.03.04,0,.08,0,.1-.02.04.02.08.02.13-.02.05-.04.08-.06.1-.06.04,0,.09-.01.13-.05l.12.07-.03.03c-.06-.03-.12.01-.17.11-.02,0-.03,0-.03.03.02,0,.03,0,.03,0h.06c.05-.05.09-.07.13-.05l.07-.03s.05-.04.07-.06c.04-.02.1-.03.16-.05.02,0,.03.01.03.03l.03.03s.05-.02.1,0c.04,0,.08-.01.1-.06l.07-.03c.15,0,.29-.03.42-.06.13-.03.24-.05.33-.07l.2-.05s.04-.02.06,0c.04,0,.07.03.09.07l.03.07.03.03-.04.09-.37.22-.11.12s-.02.06.03.07l.03.03s0,.01,0,.03c0,0-.01,0-.03,0l-.34.16c-.18.07-.31.13-.4.19-.07.02-.14.06-.24.14v.03s.03,0,.03,0l.3-.1h.03s-.09.04-.13.06c-.04.02-.09.05-.14.08,0,0-.05.04-.14.12l-.1.09-.13.05v.06s.06,0,.06,0l.26-.07.29-.04c.22-.07.39-.1.52-.12,0,.04-.02.07-.04.09,0,0-.01,0-.03,0t0,0h-.03s.03.06-.04.06h-.03s-.1.02-.1.02l.02.1s0,.03,0,.03c.02,0,.03,0,.03,0l.42-.06h.03s.07-.02.07-.02l-.04.06v.06s.18.05.18.05c.04-.02.08-.04.1-.06.04-.02.1-.02.16-.02.09,0,.15,0,.19-.02h.03s0,.03,0,.03h-.03s-.07.06-.07.06l.16.05.22.02s.03.01.03.03c.08.09.12.14.12.14v.03s-.03,0-.03,0c0-.02,0-.03-.03-.03-.04-.05-.08-.06-.12-.04-.04.02-.08.03-.1.02l-.04.06h.06c.06.01.11.06.15.15,0,0,0,.01,0,.03.02,0,.04,0,.07-.03h.16s0,0,0,.01h.03s-.03,0-.03,0c-.09.04-.16.09-.21.17l-.07.03c-.17.03-.29.04-.36.03-.19-.02-.34,0-.45.06-.11.05-.19.07-.23.04l-.13.02-.93.3-.34.16-.63.23-.3.17-.37.16c-.07.04-.13.06-.2.08-.07.02-.12.03-.16.05l-.13.05-.31.29s-.04.07-.05.16l.03.07-.04.06s0-.03-.03-.03c-.02-.07-.06-.1-.12-.11l-.06-.04c-.14-.16-.2-.24-.2-.24l-.15-.11-.07.03-.34.16-.1.02-.37.19-.07.09s-.08.05-.1.02c0-.02-.02-.03-.06-.04-.13.05-.21.09-.23.11-.02.02-.06.04-.1.06-.04.02-.09.06-.14.12,0,.06-.04.09-.1.09-.17.03-.31,0-.41-.07-.02-.02-.05-.04-.09-.04-.11,0-.26-.07-.47-.17v-.03s-.09-.06-.15-.05c-.04.02-.08.03-.1.02-.07.04-.17.07-.3.1-.15.03-.26.02-.32-.03ZM.75,38.97h-.03s-.06-.04-.06-.04c0,.02-.02.03-.07.03l.06.04h.06s.03-.02.03-.02ZM.49,38.63c.06,0,.11,0,.13-.02h.03s-.03,0-.03,0c-.04-.03-.11-.04-.22-.05h-.06s0,0,0,.03c0,0,.01,0,.03,0l.03.03h.1ZM.56,37.86c0-.06.02-.11.04-.12l.12-.25v-.06s-.03.03-.03.03l-.2.4.03.03.03-.03ZM.91,38.25l-.02-.1s-.03,0-.03,0c0-.02,0-.03,0-.03l.03-.03s0,.01,0,.03c0,0,.01,0,.03,0v.03s.03,0,.03,0c0-.02,0-.03,0-.03l.09-.25s.04-.1.05-.19c.05-.04.05-.07,0-.1v-.03s-.02-.07-.02-.07c0,0-.02.02-.07.06,0,.11-.04.19-.09.25l.03.03h.03s.03.04.03.04l-.04.06c-.06-.03-.08-.03-.06,0,0,.02,0,.04,0,.06h.03s-.03,0-.03,0h-.03s-.02.05-.04.09c-.05.04-.05.08-.01.13,0,.04,0,.06.03.07,0,.02,0,.03.03.03l.04-.06ZM1.65,38.95c.09,0,.15,0,.19-.02v-.03s-.03,0-.03,0l-.1.02v-.03s-.06.03-.06.03c-.02,0-.03,0-.03.03h.03ZM2.05,38.73s.03,0,.03,0c0-.02,0-.03,0-.03h-.03c-.06,0-.12,0-.16.02v.03s.16-.02.16-.02ZM1.42,37.91s.01-.03.03-.03c-.02-.02-.03-.06-.02-.1l-.04.06s0,.06.03.07ZM.88,37.12l.04-.12h-.03s-.04.09-.04.09v.06s.03-.03.03-.03ZM1.32,37.19s.02-.02.07-.06l-.06-.04v-.03s-.03-.03-.03-.03h-.03s0,.09,0,.09c0,0,.02.02.06.07ZM2.3,38.88l.78-.09.16-.02.03-.03h-.06s-.65.03-.65.03l-.1.02-.03.03h-.06c-.09-.01-.17,0-.26.04-.02,0-.03,0-.03.03h.03s.19-.01.19-.01ZM2.87,38.96s.08,0,.1-.02l-.09-.04s-.06.03-.1.02c.02.02.05.04.09.04ZM3.06,38.63h.03s-.03-.03-.03-.03c-.22.02-.37.05-.46.09h-.03s0,0,0,.03c0,0,.01,0,.03,0l.46-.09ZM1.44,36.98s0-.04.04-.06l.04-.06s0-.1.08-.15c0-.02.01-.03.03-.03,0-.02,0-.03,0-.03-.02,0-.03,0-.03,0,0,0-.02,0-.06,0l.04-.06.04-.06s0-.03,0-.03c-.02,0-.03,0-.03,0l-.07.03c0,.06-.03.14-.08.22l.03.03h-.03s-.05.05-.07.09c-.02.04-.04.07-.04.09v.06s.09.04.09.04l.04-.06ZM2.61,38.62c.22-.05.36-.08.43-.09h.03s-.03,0-.03,0l-.45.06v.03s.03,0,.03,0ZM1.23,36.41c.05-.08.08-.14.08-.19v-.03s-.11.18-.11.18l.03.03ZM3.26,38.87c.08.05.15.04.19-.02.02-.02.07-.03.13-.02l.13-.02s.01,0,.03,0c.04,0,.07-.02.07-.06h.03c.09.01.14,0,.16-.02l.03-.03-.06-.04s-.06.03-.1.02c-.06,0-.12.03-.17.11l-.19-.05-.26.07v.03ZM1.68,36.42s.06,0,.07-.03c.02-.02.06-.06.11-.12.03-.06.03-.13.02-.19-.02-.02,0-.05.04-.09,0-.02.01-.03.03-.03.02-.02.01-.04-.03-.07v-.03s-.06.03-.06.03l-.12.25v.06s0-.03.03-.03l.03-.03v.03c-.1.08-.14.12-.14.12l-.04.09.06.04ZM2.16,36.43s-.03,0-.03,0c0-.02,0-.03,0-.03v.03s-.08,0-.1.02v.03s.03.03.03.03l.1-.09ZM4.18,38.69s.08,0,.1-.02v-.03s-.09,0-.09,0v.03s-.1,0-.1,0c.02.02.05.04.09.04ZM2.03,35.74h.03s0-.03,0-.03c-.02-.04-.02-.07,0-.06.02-.02.05-.03.07-.03,0-.02.03-.05.07-.09,0-.02,0-.04,0-.06-.02-.02-.03-.03-.03-.03-.04,0-.07.02-.07.06l-.14.18v.1s.06-.03.06-.03ZM3.01,36.99l.12-.21-.03-.03s-.01,0-.03,0c0,0,0,.01,0,.03l-.12.21v.06s.06-.06.06-.06ZM4.09,38.24s-.03,0-.03,0c0-.02,0-.03,0-.03-.02,0-.04,0-.07.03,0,0-.01,0-.03,0,0,.02.02.03.06.04l.07-.03ZM2.4,35.87s0,.03.03.03c0-.02,0-.03,0-.03l-.02-.1s-.03,0-.03.03c0,.04,0,.06.03.07ZM6.22,41.09s0-.03,0-.03c0-.02.03-.05.07-.09.02.02.02.03,0,.03,0,.02-.03.05-.07.09ZM4.37,38.29s.03,0,.03,0c0-.02,0-.03,0-.03h-.03s-.11,0-.2.04h.03s.16-.02.16-.02ZM4.32,38.19s.08,0,.1-.02c0-.02-.02-.03-.06-.04,0,0-.02.02-.07.06,0,0,0,.01,0,.03.02,0,.03,0,.03-.03ZM2.28,35.41l.08-.19v-.1s.01-.03.01-.03c-.02,0-.03,0-.03,0-.02,0-.03,0-.03.03v.03s0,.06,0,.06c-.06,0-.1.03-.11.12-.02.02-.02.04,0,.06,0,0,.01,0,.03,0h.06ZM2.48,35.65s.01-.03.03-.03c0-.02.01-.03.03-.03v.03s0,.03,0,.03h.03s0-.09,0-.09v-.03s-.06,0-.06.03l-.03.03v.06ZM4.51,38.24c.09,0,.17,0,.26-.04h.03s0-.03-.03-.03l-.26.07ZM6.13,40.28s.11-.01.2-.05l.03-.03h-.03s-.23,0-.23,0c0,.02-.01.03-.03.03l.06.04ZM2.48,34.95s.01-.03.03-.03c0-.02.01-.03.03-.03l.07-.09s-.02-.04,0-.06c.02-.02.03-.03.03-.03.05-.12.1-.21.15-.24l.11-.18v-.06s-.04-.05-.09,0c0,.02-.03.07-.08.15l-.11.15-.12.21c-.05.08-.08.13-.08.15-.02.02-.04.04-.04.06,0,.02-.01.04-.04.06,0,.02,0,.03,0,.03-.02,0-.03,0-.03,0l.06.04.07-.12ZM4.98,37.54h-.03s-.05.01-.1.05v.03s.13-.08.13-.08ZM2.93,34.15s.03,0,.03,0c.02-.02.05-.04.07-.06l-.06-.07-.1.09.06.04ZM5.61,37.37s-.09-.03-.16-.01c-.04,0-.08,0-.1.02l-.04.06h.06s.23-.07.23-.07ZM3.13,33.78l.03.03s0-.03,0-.03c.02,0,.03,0,.03,0v-.03s-.09,0-.09,0l-.04.06.07-.03ZM5.9,37.33s.02-.03.07-.03l-.09-.04-.07.03-.03.03h.03s.1.01.1.01ZM6.2,37.65l.1-.06s-.06.03-.1.02l-.07.03h-.03s.03,0,.03,0h.06ZM3.31,33.57s.01-.04.04-.06.02-.04,0-.06l.03-.03.07-.12s0-.06-.03-.07l-.04.06-.04.06-.07.12s-.01.04-.04.06l-.04.06s0,.01,0,.03c.02,0,.03,0,.03-.03l.07-.03ZM7.23,37.99s.03,0,.03-.03c-.02,0-.05-.02-.09-.04-.04-.02-.07-.03-.1,0-.02,0-.08.01-.16.05l-.03.03h.03s.06,0,.06,0h.03c0,.07,0,.09.03.07s.05-.03.07-.03l.13-.05ZM3.61,33.05s.03-.05.07-.09l-.03-.07-.07.09.03.07ZM7.14,38.28c.15.01.27.01.35,0,.13-.03.27-.07.43-.12.04,0,.06,0,.07-.03h-.06s-.06-.01-.06-.01l-.16.02c-.13-.03-.22-.02-.29.04l-.26.07s-.03,0-.03.03h.03ZM7.12,36.96v-.03s-.06,0-.06,0l-.1.02-.03.03.06.04.13-.05ZM7.32,37.3c.09-.01.22-.06.4-.13l.03-.03h-.06s-.06-.01-.06-.01l-.03-.03v.03s-.03.06-.07.06c-.02-.02-.03-.03-.03-.03l-.03-.03s0,.06.03.07c0,0,0,.01,0,.03,0,0,.01,0,.03,0h-.06s-.06.02-.1.02c-.02,0-.04,0-.07.03l-.03.03h.06ZM8.38,36.55s.01-.03.03-.03l.26-.04.43-.16h.03s.06.04.06.04l-.03.03c-.07.04-.17.07-.3.1-.13.03-.21.05-.23.04l-.07.03c-.06,0-.09.01-.07.06l-.12-.07ZM9.73,35.74l.07-.12s.07-.03.13-.02v.03s-.04.07.02.1h.03s-.03,0-.03,0h-.23ZM10.87,36.03s-.03,0-.03,0c0-.02,0-.03,0-.03-.14-.12-.22-.2-.24-.25-.02-.04-.05-.08-.09-.1-.02-.02-.04-.04-.06-.04l-.22-.08-.13.02h-.03s.03,0,.03,0l.13-.05.12.04s.03.01.03.03c.02,0,.03,0,.03-.03.02-.02.04-.02.06,0l.06.04c.17.21.27.34.29.41.02,0,.03.01.03.03ZM15.82,41.57c-.11,0-.2-.06-.28-.15l-.12-.04c-.15-.01-.27-.08-.37-.19-.08-.03-.15-.08-.21-.15-.08-.07-.18-.11-.31-.12-.02.02-.07.02-.13-.01-.06-.03-.11-.04-.16-.05l-.4-.23c-.13-.2-.29-.36-.47-.46-.12-.07-.21-.12-.28-.12-.11,0-.18-.08-.21-.21-.04-.07-.16-.15-.36-.26-.16-.08-.34-.28-.53-.59-.04-.07-.12-.3-.26-.7-.03-.13-.03-.25,0-.35h-.03s.13-.35.13-.35c.06-.17.09-.28.09-.35l.09-.25s.08-.1.11-.18c.03-.08.04-.14.05-.16-.06-.07-.07-.12-.05-.16.05-.06.07-.1.07-.12.03-.15.1-.27.19-.37.08-.16.16-.36.24-.59.03-.1.11-.26.23-.46.05-.08.2-.34.45-.76.08-.21.16-.37.24-.49.08-.14.14-.27.19-.37.12-.16.23-.35.34-.58.12-.1.18-.23.2-.4l.04-.12.12-.21s.04,0,.07-.03c.02-.02.04-.04.04-.06l.07-.09c.2-.33.31-.53.34-.61.1-.14.18-.27.26-.4.08-.14.14-.26.19-.34l.3-.49c.03-.06.08-.18.16-.34.08-.16.17-.31.26-.43.12-.18.2-.34.23-.46l.24-.49c.07-.08.12-.15.15-.21.03-.08.06-.15.08-.19,0-.06.05-.16.12-.28.04-.02.06-.05.04-.09,0-.06,0-.11-.02-.13l-.18-.14s0-.04-.03-.07c0-.04.02-.07.04-.09,0-.11,0-.18-.04-.23v-.06s.02-.13.02-.13c-.03-.15.02-.23.15-.24.05-.04.12-.07.23-.11.26-.08.49-.2.67-.36.04,0,.07-.03.07-.09l.32-.71s.03-.08.01-.13c0-.04.02-.09.05-.16.03-.04.06-.11.12-.21.07-.12.16-.2.25-.24.16-.14.36-.19.59-.17.21.02.37.04.48.07.1.03.21.1.3.22.06.03.12.06.18.11.06.05.12.09.18.11.02.04.07.09.15.14.1.05.17.09.21.12l.27.25s.09.07.15.08c.22-.05.39-.1.53-.18.46-.17.9-.31,1.32-.4.31-.14.62-.25.93-.3.29-.08.51-.12.68-.1l.22.02.29.02s.07.02.16.05c.08,0,.15.04.18.11.02.02.05.04.09.04.04,0,.08.02.12.04.02.02.05.04.09.04.02,0,.03.01.03.03h-.03s-.04,0-.07.02c0,.02,0,.03,0,.03l.03.07-.03.03.02.1.22.05.06.07s.04.06.06.1c.02.02.04.07.05.13,0,.06.01.11.05.13.04.02.07.05.09.07.02,0,.05.06.08.17.04.02.07.05.09.07.04.02.07.05.09.07.08.09.09.19.04.29-.01.13-.03.22-.06.28l.02.19c.01.09,0,.17-.02.26l-.13.37-.11.21h-.06c-.04-.05-.03-.12.02-.2.02-.02.04-.05.04-.09,0-.06,0-.11-.02-.13-.02-.04-.04-.09-.05-.13-.02-.04-.07-.07-.15-.08-.02,0-.03.02-.04.06l-.04.06v-.06s-.02-.07-.02-.13l-.19-.02h-.1c-.06-.04-.15-.04-.25-.03-.31.1-.54.17-.69.2-.26.08-.66.2-1.19.35-.44.09-.75.17-.95.24-.11.03-.27.08-.49.15-.22.05-.4.07-.55.08-.07.02-.14.04-.23.08-.07.02-.14.04-.23.08-.13.03-.2.05-.2.05-.13.03-.24.04-.32.04-.02.02-.07.04-.13.05-.06,0-.1,0-.1.02l-.08.15-.31.62c-.05.08-.12.19-.22.33-.07.12-.14.24-.19.37-.12.2-.21.37-.27.49-.07.12-.16.24-.26.36-.07.12-.15.25-.23.4l-.11.15v.03s.06,0,.06,0l.4-.13c.13-.01.25,0,.35.03.04.02.17.05.38.07.06,0,.1.04.12.11.02.02.05.04.09.04.19.08.3.12.34.13v.06s-.04,0-.04,0c-.02,0-.03,0-.03.03,0,.02-.01.03-.03.03.02,0,.03.01.03.03,0,.02,0,.03.03.03l.22.05h.03s.12.11.12.11l-.13.05c-.08,0-.14,0-.16.02h-.03s0,.03.03.03l.09.04.32.03s.1.03.19.08c.03.11.08.18.14.21l.19.05c.06.03.09.06.09.1,0,.02-.01.03-.03.03l-.25-.09h-.06s.03,0,.03.03c.02.07.05.12.11.17.08.03.15.06.19.08l.26.28s0,.01,0,.03c0,0,.01,0,.03,0h-.1s0-.04-.03-.04c-.02,0-.03,0-.03,0-.01-.09-.03-.11-.06-.07-.02.02-.05.03-.07.03l.02.13.15.14s0,.01,0,.03c.02.02.04.04.06.04-.04,0-.08-.03-.12-.07h-.03s-.02,0-.06,0l.02.1c.17.06.28.12.34.19l.14.24.06.07s.04.06,0,.1c-.02.02-.06.03-.1.02l-.18-.11-.28-.12c-.08-.05-.11-.02-.07.09v.03s-.03-.03-.03-.03c-.02-.04-.07-.06-.16-.05l-.98.14-.91.15-.26.07c-.33.06-.64.1-.94.14-.11.01-.22.03-.33.07-.11.01-.24.02-.39.03-.04,0-.12.01-.23.04-.11.01-.22.01-.32,0l-.1.06c-.13.29-.23.47-.31.55l-.14.15c-.15.24-.31.53-.49.86-.07.12-.15.27-.23.43-.06.15-.14.3-.26.46-.26.58-.43.95-.48,1.11-.03.08-.06.18-.09.28-.03.08-.05.19-.06.32-.03.08,0,.12.09.1.07-.04.12-.05.16-.05.07-.02.11-.02.13-.02h.03s-.03.01-.03.03l-.33.13s-.04,0-.07.03c0,0-.01,0-.03,0h.13s.26,0,.26,0h.06s-.03.03-.03.03l-.3.07c-.07.02-.11.04-.14.08-.02.02-.03.06-.01.13,0,.02,0,.04,0,.06.02,0,.03.01.03.03,0,.04.04.07.12.07h.26c.07-.03.14-.04.23-.05.11-.03.22-.05.32-.04h.06s.04,0,.06.01c.04,0,.07.02.09.04.08.09.15.12.22.08l1.02-.23.43-.12h.06s.11,0,.2-.04c.09-.04.18-.06.26-.07.04-.02.11-.04.2-.08.11-.05.22-.09.33-.1.02,0,.16-.04.43-.12.13-.03.23-.07.3-.1.09-.04.17-.06.23-.08.17,0,.26-.02.26-.04l.04-.06s.03.01.03.03c0,.02,0,.03,0,.03.07-.06.1-.04.09.04.02.02.04.04.06.04.04,0,.06,0,.07-.03h.03s.06,0,.06,0v-.03s0-.06,0-.06c0-.02.01-.03.03-.03v.03s-.01.1-.01.1c0,0-.02.02-.07.06v.06s0,.04-.01.06c.02,0,.03.01.03.03.02.02.08.07.18.14.02,0,.03.01.03.03.07.18.14.27.2.27.02,0,.03,0,.03-.03.02-.02.05-.03.07-.03l.03-.03s0,.01,0,.03c.02,0,.04,0,.06,0v.03s-.01.13-.01.13c.02,0,.06-.02.1-.06.05-.04.07-.07.07-.09,0,0,0-.01,0-.03.02-.02.04-.04.04-.06.02,0,.03.01.03.03,0,.02,0,.03.03.03v.03s-.06.09-.05.16c.02.02.03.07.02.13.03.11.09.15.18.11.07-.02.12-.01.16.01.06.09.05.2-.03.32-.09.06-.13.13-.11.21.01.09.02.14.02.16l-.03.32-.03.03s-.01,0-.03,0c-.02,0-.03-.01-.03-.03-.06-.03-.1-.07-.12-.14-.02-.04-.04-.06-.06-.04-.1.12-.25.19-.47.22-.11.03-.24.06-.39.09-.13.03-.27.07-.43.12-.13.03-.27.08-.43.16h-.03s-.08-.02-.13.02c-.05.04-.08.06-.1.06l-.03.03h-.13c-.03.05-.07.09-.14.11-.07.02-.11.02-.13.02l-.19.02c-.13.03-.23.11-.31.23h-.03c-.06,0-.15,0-.26.04-.11.03-.2.06-.26.07l-.27.11s-.05.02-.1.06c-.06,0-.1,0-.1,0h-.06c-.06-.01-.14,0-.23.04-.09.06-.17.09-.23.11l-.14.08-.23.08h-.1ZM15.1,39.1l.07-.06h-.06c-.06-.01-.11,0-.13.05l-.03.03h.06s.1-.02.1-.02ZM13.46,36.51l.04-.12s0-.03-.03-.03v.03s-.04.06-.05.12h.03ZM15.4,38.99c.11,0,.18,0,.23-.01h.03s-.03-.03-.03-.03l-.23.04h-.03s0,0,0,.03c.02,0,.03,0,.03-.03ZM13.66,36.05s.07-.09.08-.15v-.03s-.03,0-.03,0l-.07.12v.06s.03,0,.03,0ZM17.8,39.78s.05-.06.07-.06c.02,0,.04,0,.07-.03l.36-.13c.06,0,.14,0,.23-.04l.04-.06-.07.03c-.22.02-.38.06-.49.12-.05.04-.11.08-.2.11-.02,0-.03.02-.04.06h.03ZM17.85,39.18c.13-.05.27-.09.4-.13.13-.03.24-.06.33-.1l.07-.03s-.06,0-.06,0l-.43.09s-.1.04-.17.08c-.04.02-.1.04-.17.08h-.03s.03,0,.03,0h.03ZM18.98,38.76c.15-.03.27-.07.36-.13h.13s-.16-.03-.16-.03c-.13.07-.25.12-.33.13,0,0,0,.01,0,.03,0,0-.01,0-.03,0h.03ZM25.87,27.22v-.06c.01-.06.03-.11.05-.12h.03s-.05.22-.05.22h-.03s0-.03,0-.03ZM27,42.77s-.05-.03-.09-.07v.06s-.09-.1-.09-.1l-.03-.03c-.06-.03-.16-.05-.28-.06-.04-.02-.1-.04-.19-.05-.02,0-.05,0-.1,0-.02.02-.07.02-.13-.01l-.19-.05s-.09-.04-.16-.05c-.07.02-.12.02-.16.02h-.1s-.41-.14-.41-.14h-.1s-.05-.03-.09-.08l.03-.03c.03-.08.07-.12.14-.12.06,0,.11,0,.13.01.02.02.03.02.03,0,.02,0,.04,0,.06,0-.04,0-.07-.02-.09-.04-.11,0-.18-.03-.22-.05,0,0-.01,0-.03,0,0,0,0-.01,0-.03v-.03c.09-.04.16-.07.21-.11-.09.04-.16.05-.23.04-.11.03-.18.03-.22-.02-.12-.05-.23-.07-.32-.06-.04.02-.11.02-.19.02-.17-.01-.34-.1-.52-.27-.24-.21-.48-.57-.71-1.06-.19-.32-.32-.55-.39-.71-.14-.35-.22-.62-.25-.79-.06-.33-.07-.68-.04-1.06l.02-.19c0-.11.05-.17.11-.18.02,0,.03-.03.04-.09l.09-.31v-.06s.08-.09.08-.09v.1s-.04.32-.04.32v.06s.08.07.08.07v-.06s.06-.64.06-.64v-.03s.12-.18.12-.18c.05-.04.07-.06.07-.06l.03.07v.06s.06-.06.06-.06l.05-.16c.05-.08.08-.14.08-.19.01-.17.04-.3.07-.38,0-.04.02-.13.05-.25.03-.15.09-.28.16-.4.07-.08.12-.15.15-.21.05-.08.1-.15.15-.21,0-.02,0-.04,0-.06.02-.02.02-.04,0-.06v-.03s.1-.1.15-.18c.07-.1.13-.18.18-.24.02-.02.04-.04.04-.06,0-.04.02-.07.04-.09,0-.02.03-.05.07-.09s.06-.09.05-.16h.03c.07-.01.08-.03.04-.06-.02-.04-.02-.07,0-.06v-.03c-.06-.03-.08-.06-.05-.1.1-.12.16-.21.18-.27l.04-.06-.07.03c-.05.08-.1.16-.15.24-.05.06-.08.11-.11.15-.07.08-.16.2-.26.36-.05.1-.13.26-.23.46-.1.18-.17.36-.21.53,0,.02-.03.06-.07.12-.02.04-.02.07.02.1-.04,0-.08.01-.1.06,0,.04,0,.07,0,.1-.05.04-.1.12-.15.24l-.1.41c0,.09-.03.15-.08.19-.05.04-.07.1-.08.19l-.04.06.02-.22c0-.11.05-.18.11-.21,0-.04,0-.06,0-.06.02-.23.08-.43.18-.59l.15-.24.07-.12v-.13s.25-.56.25-.56c.09-.25.24-.5.45-.76.42-.61.82-1.11,1.22-1.5.33-.4.6-.69.78-.86,0,0,.09-.08.28-.23.14-.16.26-.27.35-.32l.56-.53c.14-.16.38-.4.7-.71l.49-.47.44-.31s.1-.08.17-.11c.07-.06.12-.13.15-.21.03-.06.13-.17.32-.33.07-.08.16-.17.28-.26.12-.1.22-.18.31-.26l.12-.21c.04-.17.15-.3.35-.39l.67-.33.11-.12.07-.09c.07-.02.25-.13.54-.34l.33-.13c.18-.11.32-.21.41-.29.16-.09.39-.17.69-.23.13-.01.32,0,.58.02l.13-.02h.29c.09-.02.16-.01.22.01.06,0,.12.01.16.01.13.01.22.05.28.12.08.05.18.1.31.16.15.03.25.06.31.09l.64.35s.09.1.26.31c.02.02.03.06.02.1.1.35.11.62.03.81-.03.1-.1.24-.2.4l-.14.53s-.05.08-.07.12c-.02.02-.05.05-.07.09l-.14.18c-.06.21-.12.35-.17.44,0,.04-.08.18-.23.4l-.11.12s-.02.05-.04.09c-.02.02-.04.02-.06,0-.02,0-.03,0-.03.03-.08.14-.19.32-.33.52-.12.18-.26.41-.41.67l-.18.21s-.07.1-.08.19c-.03.13-.11.19-.24.2l-.14.15c-.1.18-.24.37-.4.54-.26.32-.41.51-.44.57-.22.3-.5.61-.85.92l-.44.22-.1.09-.14.12c-.06,0-.11-.02-.12-.04-.06-.07-.15-.1-.28-.09-.15.05-.3.09-.43.12l-.19.02c-.3-.03-.5-.24-.62-.63-.02-.07-.06-.17-.13-.3-.15-.27-.2-.51-.16-.72.01-.13.07-.32.18-.56.13-.22.24-.42.34-.58.1-.16.19-.32.26-.46l.26-.4v-.06s-.04,0-.06,0c-.02-.02-.03-.02-.03,0-.07.02-.14.06-.24.14l-.72.58-.73.61s-.14.15-.49.5l-.77.7c-.19.2-.38.42-.57.66-.07.08-.12.15-.15.21s-.05.11-.08.15l-.37.51-.34.58v-.03s-.06.02-.07.06c-.03.06-.07.13-.12.21-.05.06-.09.13-.11.21l-.25.68-.07.38v.1s.05.04.05.04l.04-.06s.01-.04.04-.06c.02-.02.04,0,.06.04.02.02.04.05.06.07.02,0,.03.01.03.03,0,.08-.03.15-.08.19l-.14.12v.03c-.06-.05-.13-.04-.2.02-.12.14-.19.28-.2.43-.02.02-.04.02-.06,0h-.03s-.06.04-.04.06c.02,0,.03.01.03.03,0,0,.02.02.06.07l.04-.09v-.06s.1-.02.1-.02h.1s-.03.02-.03.04l-.11.18-.04.09v.06s.05.07.05.07l.04-.09.12-.31.07.33.12.49.06.07.04-.09.04-.06v.03s.05.08.05.1c-.02.02-.05.05-.07.09-.02.02-.06.03-.1.02,0,0-.01,0-.03.03,0,0,0,.01.03.03.04.05.03.08-.04.09-.02.02-.04.05-.04.09.07.2.16.36.28.47.06.05.11.11.15.17l-.07.09h-.03s-.04-.02-.06-.04c-.02-.02-.02-.04,0-.06l-.03-.03s-.01,0-.03,0c0,0,0,.01,0,.03v.1c-.02.09.03.16.13.24.02,0,.04.01.06.04.04.02.05.06.02.1,0,0,.03.05.08.14l.03.07c-.03.06-.02.11.02.13.04,0,.09,0,.13-.02.24,0,.54-.03.91-.08.35-.06.61-.11.78-.16h.03s-.2.08-.2.08l-.03.03h.06s.23,0,.23,0c0,0,0,.01,0,.03,0,0,.01,0,.03,0-.02,0-.03,0-.03.03-.13.05-.21.09-.23.11-.07.02-.12.03-.16.05-.02.02-.05.04-.07.06-.02,0-.03,0-.03.03,0,0,0,.01,0,.03,0,0,.01,0,.03,0,.06,0,.14.03.22.08l.26.02v.03s.06,0,.06,0l.26-.07h.03s-.01.03-.03.03l-.49.12-.43.16-.23.04-.36.1h-.06s-.06-.06-.12-.05c-.04.02-.09.02-.13.02-.02-.02-.04-.04-.06-.04l-.09-.04s-.11-.05-.22-.02h-.13s-.03-.02-.03-.05h.03s.03-.03.03-.03l-.06-.04c-.12-.05-.21-.08-.25-.09h-.39s-.3.07-.3.07c0-.04,0-.06-.03-.07l-.13.02v.03s0,.01,0,.03c0,0,.01,0,.03,0h-.06s-.03-.07-.03-.07v.06s-.01.06-.01.06c-.04,0-.06,0-.06,0-.02-.02-.04-.02-.06,0,0,.02-.03.03-.1.02v-.03s.04,0,.04-.03l.14-.08-.03-.07s-.1,0-.16-.01c-.06-.03-.11,0-.13.05,0,.02-.01.03-.03.03l-.1.09s.07.07.09.07c.04.02.1.04.19.05,0-.02.01-.03.03-.03,0,0,0,.01,0,.03,0,0,.01,0,.03,0,0,.04.02.07.06.07l.13-.02s.07.07.09.07c.02,0,.06-.02.1-.06-.02,0-.03-.02-.03-.07h-.16s0-.05-.03-.05h.03s.16-.05.16-.05c-.02-.02-.02-.03,0-.03.02,0,.03,0,.03-.03v.06s.06-.03.06-.03h.03s.08.03.13.01c.04-.02.08-.03.1-.02h.23s.26,0,.26,0c.04,0,.07.02.09.04l-.07.03-.29.04s-.03,0-.03.03c0,.02.02.03.06.04h.13c.06.02.12,0,.16-.04.02,0,.03.01.03.03l-.07.03.06.04h.16c.13.03.28.02.45-.01.02,0,.03.01.03.03l-.1.06s-.03,0-.03.03h.03c.09.01.15,0,.19-.01l.03.03h-.03s-.07.06-.07.06h.1s.22.03.22.03l.07-.03.2-.08s0-.02,0,0c.02,0,.03,0,.03,0h.1c.03-.05.07-.07.13-.04.02,0,.07-.03.14-.08.02,0,.03-.02.04-.06l-.07.03c-.13.03-.23.04-.29.04l-.07.03v.03s-.07-.02-.06-.04c0-.02.01-.03.03-.03.05-.04.1-.06.17-.05l.3-.1h.03s0,.03,0,.03c-.02.02-.04.04-.04.06.02,0,.03,0,.03,0,.02.02.05.04.09.04.09-.04.15-.05.2-.05v-.03s-.03,0-.03,0c0-.02,0-.03-.03-.03,0-.02.01-.03.03-.03l.07-.03c.33-.1.62-.15.88-.15l-.1.02-.03.03h.06s.03-.02.03-.02v.06s.02.03.02.03l.36-.03.46-.09.06.04s-.03,0-.03.03c-.04.02-.12.05-.23.11l-.5.25.36-.07c.11-.03.2-.07.27-.11.09-.04.17-.06.23-.08l.19.05.1-.02.1-.02h.06c.13-.03.23-.06.3-.1.11-.05.24-.11.4-.16.16-.07.31-.14.47-.22l.2-.11h.03s0,.03,0,.03l-.74.35c-.13.07-.34.16-.6.27l-.07.06h.06c.11,0,.33-.07.66-.19.11-.05.23-.1.36-.13,0-.02,0-.03,0-.03.02,0,.03,0,.03,0l1.2-.47h.06s-.03.03-.03.03l-.97.46s-.02.02-.07.06c0,0-.02.02-.07.06.06,0,.1,0,.1-.02l.46-.15c.34-.16.5-.25.5-.25l.47-.18c.07-.02.12-.03.16-.05.07-.02.12-.03.17-.05l.4-.16.2-.08s0-.02,0,0c.02,0,.03,0,.03,0v.03s-.06.02-.1.06c.06,0,.11,0,.13-.02l.4-.19.1-.06v.03s0,.03,0,.03h.03s.17-.08.17-.08h.06s-.03.01-.03.03l-.48.34-.78.51c-.13.07-.28.15-.44.22-.16.07-.31.15-.47.25-.29.1-.53.21-.73.32l-.09-.04h-.03s-.01,0-.03.03c0,0,.01,0,.03,0,.02.04,0,.08-.04.09-.02.02-.05.03-.07.03-.36.18-.6.3-.74.35-.31.14-.49.22-.53.24-.05.04-.09.06-.13.05-.02.02-.05.03-.07.03h-.03s0-.03,0-.03l.24-.17.47-.18.2-.08s.02-.02.07-.06h-.1s-.33.12-.33.12c-.11.05-.24.1-.4.13-.16.07-.39.16-.7.26-.04.02-.07.04-.07.06,0,.02-.01.04-.04.06l.03.07s.02-.06.04-.06c.04,0,.07,0,.1,0l.17-.08.13-.05h.1s-.04.07-.04.07l-.37.16c-.07.04-.12.04-.16.02l-.07.06-.1.02c-.06,0-.11,0-.13.02-.03.06-.08.1-.17.11-.07.02-.12.03-.16.05l-.2.08s.08-.1.18-.18l.1-.06s0-.03-.03-.03h-.13c-.08-.04-.16-.05-.22-.03-.07.04-.16.06-.26.07-.11.03-.2.06-.26.07h-.03s0-.07,0-.07c-.04-.02-.09-.02-.16.02v.1s-.01.03-.01.03c-.04,0-.06,0-.07.03l-.14.08c.06,0,.11,0,.13-.02.06,0,.12-.01.16-.05h.03s-.01.03-.03.03c-.05.06-.08.1-.11.12-.23.17-.49.23-.78.16ZM23.85,41.34l-.15-.14-.09-.07-.03.03s0,.06.03.07c.12.07.19.12.21.15h.03s0-.03,0-.03ZM24.08,41.23s.03,0,.03-.03h-.03c-.06-.03-.17-.05-.32-.06v.03s.31.06.31.06ZM23.26,39.65s-.01,0-.03,0c0,0,0-.01,0-.03v-.06s-.05-.07-.05-.07l-.07.03s.02.02.06.07l.03.07h.06ZM23.09,39.37l-.06-.1-.07.03.09.1.03-.03ZM25.02,41.6v.03s.06,0,.06,0l.46-.09c.09,0,.1-.02.04-.09-.04-.05-.06-.05-.06,0l-.07.03s-.05,0-.1.02c-.02.02-.04.02-.06,0-.02-.02-.12-.02-.29,0l-.13.02-.1.02h-.03s-.02-.07-.06-.07c-.02.02-.03.02-.03,0-.02,0-.03,0-.03.03-.02.02-.06.03-.1.02-.04.02-.08.01-.1,0-.04-.05-.1-.07-.19-.08l-.12-.07h-.06s.06.06.06.06l.46.2h.16s.29-.02.29-.02ZM24.38,40.74l-.12-.07-.03.03s.05.03.09.07l.07-.03ZM24.6,40.85s.03,0,.03-.03c-.08-.05-.15-.08-.22-.08h-.03s0,.03,0,.03c.02,0,.03,0,.03,0,.08.05.14.08.19.08ZM22.97,39.24s.03-.02.04-.06l-.03-.07-.08-.17s0-.06-.02-.13c-.01-.09-.05-.15-.11-.2h.03s0-.03,0-.03c-.02-.07-.01-.12.01-.16l-.06-.04h-.03s-.06-.04-.06-.04v.03s.05.13.05.13c.03.13.06.24.1.33,0,.02.01.08.05.16l.08.2.03.03ZM24.94,41.33s.06,0,.07-.03c0-.06.06-.09.17-.08v-.03s-.03,0-.03,0h-.13c-.13-.02-.21-.04-.25-.07l-.07.03s.03.01.03.03c.02.02.04.04.06.04.04,0,.07.02.09.04,0,.02,0,.03.03.03.02,0,.03.01.03.03ZM24.05,39.81s-.05-.06-.15-.17l-.04.06c.08.05.14.1.18.14v-.03ZM25.34,41.21l-.03-.03s-.06.02-.1.06h.03s.1-.02.1-.02ZM22.67,38.28s.06,0,.07-.03v-.1s-.05-.04-.05-.04l.02-.19v-.35s-.06-.04-.06-.04l-.04.06-.02.22.06.39.03.07ZM23.32,38.59l-.06-.07v.03s.05.1.05.1v-.06ZM23.26,38.46l-.02-.13-.04.06.06.1v-.03ZM25.43,40.86s.03,0,.03-.03h-.03s-.22-.05-.22-.05h-.03s-.07.02-.07.02l.03.03.29.03ZM24.24,39.47l-.09-.1h-.03s.06.08.06.1c.02,0,.03.01.03.03h.03s0-.03,0-.03ZM23.21,38.29l-.02-.13s-.03.02-.04.06l.02.1.03-.03ZM23.74,38.92s0-.08-.02-.1v-.06c-.06,0-.09-.02-.09-.04,0-.04,0-.07,0-.1h-.03s-.01,0-.03.03c0,0,.01,0,.03,0,0,.08.02.16.08.23,0,.02,0,.03,0,.03.02,0,.03,0,.03,0h.03ZM24.14,39.11s-.01-.08-.05-.16l.02.16s0,.03,0,.03c.02,0,.03,0,.03,0v-.03ZM23.37,38.4c-.01-.09-.03-.17-.04-.26-.01-.11-.04-.21-.07-.3,0-.02,0-.03,0-.03.02,0,.03,0,.03,0l.11.59h-.03ZM23.12,37.93s.03,0,.03,0c0-.02,0-.03,0-.03l-.04-.29s0-.03-.03-.03v.03s0,.15.03.32ZM25.52,40.97c.08,0,.16,0,.23-.01.08.03.2.05.35.06l.13-.05-.09-.04-.35-.03c-.06-.03-.1-.03-.13-.01,0,.02-.01.03-.03.03v-.03s0-.03-.03-.03h-.03s.01.07,0,.09c-.02,0-.04,0-.06,0l-.03.03s.06,0,.06,0ZM26.14,41.18l-.06-.04-.07.03.09.04.03-.03ZM26.86,41.82l-.03-.03-.14.08.03.03.14-.08ZM27.02,42.57l.33-.07s.02-.02.07-.06l.03-.03v.03s.06.04.06.04l.03-.03s.02,0,0-.03c0,0-.02-.02-.06-.07l.04-.06h.1s-.06-.03-.06-.03h-.03s0-.03,0-.03c.02,0,.03,0,.03,0,.09-.04.16-.07.2-.11l.07-.06h-.1s-.1-.02-.1-.02h-.1s-.33.09-.33.09c.02-.02.04-.05.04-.09h-.1s-.01.02-.03.02h-.06s.07-.06.07-.06l.03-.03h.1c.13.02.26,0,.39-.05l.04-.06h-.06s-.2.04-.2.04l-.03-.03s.05-.07,0-.1c-.04,0-.06-.02-.06-.04,0,.02-.02.03-.07.03l-.07.06-.23.08c-.07.04-.08.08-.04.12,0,.02-.02.04-.07.06-.02.04,0,.05.09.04l.03.07s-.06.02-.1.06l-.36.1s-.03.05-.07.09c.02,0,.03,0,.03,0,.02.02.04.03.06,0,.06,0,.2,0,.42-.03l.06.04-.07.03-.07.03.09.07h.03ZM26.53,41.15c.07-.06.1-.09.1-.09l-.06-.04s-.08.06-.1.06c0,.04.02.07.06.07ZM27.75,42.28l-.03-.03s-.02.02-.07.06l.06.04.04-.06ZM23.75,39.56s.07-.07.07-.09c0-.06-.02-.13-.08-.2l-.13-.33c-.03-.13-.07-.27-.12-.43-.03-.15-.06-.32-.09-.49l-.03-.03h-.03s.01-.13.01-.13c-.02-.22-.05-.38-.09-.49l-.02-.16.04-.12v-.29c.02-.1.06-.24.09-.41.04-.17.06-.29.07-.38l.08-.19c.05-.08.11-.23.17-.44l-.03-.03s-.02.03-.07.03l.04-.06v-.06s0-.03-.02-.03l-.03.03-.12.25c-.05.1-.11.3-.18.59-.03.1-.05.25-.07.44l-.07.77v.29s.1.39.1.39c0,.21.04.43.1.65.07.2.11.33.13.4l.08.17v.06s-.05.02-.01.06c.02.04.07.11.14.21,0,.02,0,.03.03.03.02,0,.03,0,.03,0ZM25.36,39.44s0-.03,0-.03c.02,0,.03,0,.03,0,0-.02,0-.03-.03-.03,0-.02,0-.04,0-.06l-.04.09s0,.01,0,.03c0,0,.01,0,.03,0ZM26.63,40.71v-.03s-.06-.04-.06-.04h-.06s-.06,0-.07.02c.02,0,.03.01.03.03h.03s.13.01.13.01ZM23.73,37.53l-.03-.81s-.01,0-.03,0c0,0,0-.01,0-.03v.06s-.02.13-.02.13c-.01.17-.01.38,0,.64l.03.03.03-.03ZM25.4,40.09s0,.03,0,.03c.02-.02.04-.04.04-.06.04,0,.07-.02.07-.06l-.11-.17c-.07-.18-.13-.31-.19-.4v-.06c.07.03.09.02.07-.03,0-.04,0-.06,0-.06l.07-.09.06.07s.02.02.06.07l.03-.03-.06-.1s0-.03-.03-.03v.03s-.06-.04-.06-.04l.07-.03s0-.06,0-.06l-.08-.2c-.09-.18-.14-.33-.15-.46,0-.06,0-.16-.04-.29l-.02-.52s-.02-.06-.06-.1v.1s-.02.13-.09.25c0,0-.01,0-.03.03,0,0,0-.01,0-.03l-.03-.07v-.23s-.04-.03-.04-.03v.03s0,.06,0,.06c0,.06,0,.15,0,.26.01.09,0,.16-.02.22.02.04.01.09-.01.13v.13c-.02.11-.02.33,0,.68,0,.02,0,.04,0,.06.02,0,.02.01,0,.03-.02.04-.04.09-.05.16,0,.06,0,.12.02.16l.23.34s.03.01.03.03h-.1s-.03.02-.03.02c.02.02.03.05.03.07,0,.02,0,.03.03.03.06.03.2.08.4.16ZM23.92,37.23s.06,0,.07-.03c.02-.04.04-.07.04-.09l-.03-.03-.1.09.03.07ZM24.6,37.9v-.16s.02-.1.02-.1l-.03-.07-.04.06s.02.13,0,.26c0,0,0,.01,0,.03,0,0,.01,0,.03,0v-.03ZM23.97,37.01c0-.11,0-.18-.01-.23v-.1s-.02,0-.02,0l-.04.06v.26s0,.06,0,.06l.07-.06ZM26.86,40.34c.09,0,.17-.02.26-.07h.03s-.03,0-.03,0c0-.02,0-.03,0-.03l-.3.07s0,.01,0,.03c0,0-.01,0-.03,0h.06ZM24.6,37.16l.04-.41v-.1s-.02-.03-.02-.03l-.03.03-.07.12s-.01.03-.03.03h.06s0,.04,0,.04c.02,0,.03,0,.03,0l.02.19v.13s.02.07.02.07v-.06ZM28.98,42.23s.06-.02.1-.06l-.03-.03-.1.06s.03.03.03.03ZM24.28,36.75s-.02-.04,0-.06c.02-.04.04-.07.04-.09.05-.06.06-.1.04-.12,0-.09.03-.14.08-.15v-.06s.02-.08-.02-.13c-.02-.04-.04-.08-.06-.1,0-.02,0-.03-.03-.03,0-.02,0-.03,0-.03.02,0,.03,0,.03,0h-.03s0,.06,0,.06l-.04.06h-.03s0-.03,0-.03l-.03.03-.03.32h-.03s.05.16.05.16l-.03.03s-.03,0-.03.03c.02.02.03.03.03.03,0,.02.02.06.06.1v.03s.03-.03.03-.03ZM23.81,35.94s.01-.03.03-.03l.06-.32v-.03s-.03,0-.03.03l-.09.28.03.07ZM28,40.89v-.06s.07-.03.07-.03v.03s0,.03,0,.03c0,0,0,.01,0,.03.02,0,.03,0,.03-.03l.26-.07v-.03s.04-.06.04-.06l.27-.11s.03,0,.03-.03c0,0-.01,0-.03,0,0,0,0,.01,0,.03-.04,0-.11.01-.2.05-.09.04-.18.06-.26.07-.07.02-.13.03-.2.05l-.1.06v.03s0-.03,0-.03l.06.04h-.03s0,.06,0,.06l.07-.03ZM24.65,36.52l.08-.54-.03-.07-.04.06v.1s-.01.02-.01.06c.02.04.01.08,0,.1,0,.04-.02.07-.04.09.02.04.02.11.02.19,0,.02,0,.03,0,.03.02,0,.03,0,.03,0v-.03ZM23.92,36.11s.02-.02.07-.06v.06s0,.03,0,.03c.02,0,.03,0,.03-.03.01-.13.03-.22.06-.28.06-.17.11-.29.16-.37.03-.1.1-.26.2-.46l.12-.25v-.03s-.03,0-.03.03l-.26.43-.08.22-.07.03v-.06s.12-.25.12-.25c.11-.33.23-.57.35-.71,0,0,0-.01,0-.03,0-.02,0-.04-.03-.07h-.03c-.09.07-.15.13-.18.17l-.23.43-.12.25c-.06.17-.09.27-.09.31v.03s.03,0,.03,0c0-.02,0-.03,0-.03l.12-.28-.09.35c-.03.08-.06.18-.09.28s-.05.23-.07.38c0,.11,0,.19,0,.26l.09-.35ZM29.54,41.67s.03-.05.07-.09c-.02,0-.06.02-.1.06l.03.03ZM24.39,35.89s.03-.06.07-.06c.04.02.06,0,.07-.09l.03-.03.03.03.04-.06s0-.05-.02-.1c0-.06.02-.11.04-.12l.02-.19.07-.12s-.06-.02-.06-.04c.02-.02.03-.03.03-.03l.08-.19v-.03s-.03,0-.03,0v.03s-.01,0-.03,0c0-.02.01-.03.03-.03v-.06s.01-.06.01-.06c0,.02-.01.03-.03.03l-.12.21c-.16.31-.25.61-.27.91v.03s.03-.03.03-.03ZM24.59,35.39c.05-.08.07-.12.07-.12h-.03s-.07.12-.07.12l.03.03v-.03ZM24.82,35.7c0-.06.04-.16.09-.28h-.06s-.05.25-.05.25v.03s.03,0,.03,0ZM29.51,41.25l.17-.08s-.03,0-.03,0c0-.02,0-.03,0-.03l-.17.08v.03s.03,0,.03,0ZM28.35,39.77s.05-.03.07-.03c.04,0,.08,0,.1-.02v.03s-.17.05-.17.05v-.03ZM24.87,34.77c0-.06.03-.14.08-.22v-.03s0,.03,0,.03l-.14.18.03.03h.03ZM30.89,41.3v-.03s-.02.03-.06.03c-.04-.02-.07-.03-.1,0,0,.02-.01.03-.03.03l-.06-.04-.03.03s.06.07.06.07l.23-.08ZM24.46,33.52l-.06-.04-.11.12h.03s.14-.08.14-.08ZM25.21,34.13h-.03s-.07.09-.07.09c.02,0,.03.01.03.03l.07-.12ZM31.18,41.2v-.03s-.06,0-.06,0l-.13.05-.03.03s0,.03,0,.03c.02,0,.03,0,.03,0l.2-.08ZM31.34,41.31c.07-.02.17-.06.3-.13l.03-.03s0-.03-.03-.03l-.4.16s-.03.02-.04.06h.06s.07-.02.07-.02ZM24.91,32.88h-.03s-.18.21-.18.21c.02,0,.03.01.03.03l.18-.24ZM25.28,32.24v-.03s-.03.03-.03.03l-.14.18v.03s.18-.21.18-.21ZM26.28,33l.32-.33-.03-.03s-.02.06-.04.06c-.07.02-.12.05-.17.11-.03.06-.06.11-.11.15v.03s.03,0,.03,0ZM26.34,31.92v-.03s.08-.06.1-.06c.06,0,.1-.02.1-.09v-.06s.31-.23.31-.23l.07-.06.14-.18c.07-.04.15-.12.25-.24.02,0,.03,0,.03-.03,0-.06.06-.09.17-.08l.14-.12.17-.15v-.03s0,0-.03,0c0,0,0,.01,0,.03l-.14.15s0-.06-.03-.07c-.04,0-.04-.03,0-.06,0-.04.02-.07.04-.09l-.1.02-.31.23c-.1.14-.24.29-.42.44l-.07.12c-.12.1-.17.15-.17.15l-.35.39-.07.12h.06s.1-.08.1-.08ZM27.85,30.44l-.03-.07-.03.03s.02.07.06.07v-.03ZM27.94,30.45s.06,0,.07-.03c0,0,.03-.03.1-.09l.24-.2s.04-.05.04-.09c.02-.02.02-.03,0-.03,0-.02,0-.03,0-.03l-.07.03-.04.06-.31.26-.07.09s0,.03,0,.03c.02,0,.03,0,.03,0ZM26.71,32.43s.05-.03.07-.03c.02,0,.04-.02.07-.06.04-.02.08-.05.1-.09.05-.06.1-.11.14-.15.07-.12.16-.23.25-.33.1-.12.19-.23.29-.33l.73-.67.42-.38.32-.36.25-.24.24-.17c.07-.08.15-.15.24-.2,0-.02.01-.03.03-.03.02-.02.02-.04,0-.06h.03s.13-.05.13-.05l.31-.26s.05-.04.14-.12l-.03-.07-.03.03-.27.2-.66.52-.31.29-.35.32-.42.41-.14.15s-.06.04-.1.06c-.04.02-.08.04-.1.06l-.07.09-.28.26c-.21.24-.33.37-.35.39-.02.02-.11.12-.25.3l-.32.39-.1.09.03.03ZM28.57,29.93s.04-.05.04-.09h.03s.18-.21.18-.21h-.03c-.09.05-.14.12-.15.21-.06-.05-.09-.04-.1.02,0,.02-.01.03-.03.03l.06.04ZM30.56,28.85l.1-.09-.03-.03-.1.09v.03s.03,0,.03,0ZM30.66,28.73s0-.03,0-.03c.02,0,.03,0,.03,0,0,0,.09-.08.28-.23v-.03s-.03,0-.03,0l-.28.23v.03s0,.03,0,.03ZM36.42,47.73l-.05-.13c-.04-.09-.05-.17-.04-.23,0-.39,0-.66,0-.83h.03s.02-.54.02-.54l.09-.35c.01-.17.04-.29.06-.35.06-.17.09-.28.09-.35v-.06s-.03,0-.03,0c0,.02,0,.03,0,.03-.02.02-.04.05-.04.09-.02.04-.08.15-.16.34v.03s-.02.11-.11.18l-.09.28v.03s-.03-.03-.03-.03l.04-.12s0-.06-.03-.07l-.03-.07-.04.06-.04.12s.02.07.06.07v.03s-.03.7-.03.7l-.03.03v-.03s-.05-.55-.05-.55v-.32c.02-.23.08-.43.18-.59l.04-.06s.01-.03.03-.03v.06s-.04.09-.09.22l.03.07.03.03.06.07s0-.06,0-.06v-.03c0-.06.02-.13.05-.19.05-.06.06-.11.05-.16.04-.02.07-.06.07-.12.03-.06.04-.11.05-.16.05-.06.09-.15.12-.28.05-.1.09-.18.12-.25.09-.25.17-.42.24-.53l.15-.24c.1-.21.16-.35.17-.44v-.1c.02-.09.03-.18.07-.28.05-.1.08-.18.08-.22,0-.04.02-.06.04-.06.02-.04.06-.09.11-.15.05-.06.1-.13.15-.21.05-.06.07-.12.08-.19.03-.06.05-.12.08-.19v-.03s-.04.05-.06.03c0-.02,0-.03-.03-.03-.05.04-.07.07-.07.09-.02.04-.05.08-.07.12,0,.04-.02.08-.04.12-.07.06-.1.14-.09.25,0,.04-.03.06-.07.06l-.03-.03v-.06c.03-.06.06-.13.09-.22.03-.1.07-.19.12-.25.15-.24.26-.45.34-.61.05-.12.11-.24.16-.34.07-.1.14-.2.19-.3l.04-.06v-.03s-.03,0-.03,0c-.07.04-.13.12-.18.24-.02.04-.06.08-.11.12-.02.02-.05.04-.07.06-.05.12-.08.22-.09.28l-.07.09s0,.03.03.03v.03s-.22.24-.22.24c-.05.06-.11.14-.18.24-.05.1-.09.18-.12.25l-.35.68-.2.43-.04.09-.23.43s-.01.02-.03,0c-.02,0-.03-.01-.03-.03v-.16s.05,0,.05,0c.04.05.06.04.07-.03,0-.06.02-.11.04-.12,0-.08.04-.21.1-.38v-.03c0-.06.06-.16.16-.28l.07-.09s.01-.04.04-.06c.02-.04.05-.06.07-.06.02,0,.03-.02.04-.06v-.03c.01-.09.06-.19.16-.31.09-.25.2-.5.35-.74.07-.12.11-.19.12-.21l.13-.34c.03-.06.05-.13.08-.22.03-.1.07-.18.11-.21.03-.06.04-.12.05-.19.03-.08.07-.14.11-.18v-.06s-.06,0-.06.03c-.02,0-.03,0-.03.03,0,.11-.05.2-.12.28-.07.08-.12.14-.14.18l-.08.15c0,.09-.04.12-.11.12-.06,0-.1.03-.11.12,0,.02-.01.04-.04.06-.02.02-.05.03-.07.03l-.07.09c-.31.66-.58,1.16-.81,1.5l-.26.43s-.01.03-.03.03l-.03-.03s0-.08-.02-.1c.05-.12.1-.22.15-.28.11-.27.18-.44.21-.53v-.03s-.03.03-.03.03l-.15.24c-.12.1-.21.22-.29.36,0,0-.01,0-.03,0,0,0,0,.01,0,.03v-.03s-.02-.07-.02-.07v.06c-.08.1-.17.25-.27.46l-.07.03s.02,0,0-.03c0,0,.01,0,.03,0,.05-.12.08-.22.09-.28.05-.06.1-.17.16-.34v-.03c.07-.06.12-.14.15-.24.05-.12.09-.21.12-.25v-.06s.01-.06.01-.06l-.07.03c-.03.1-.11.24-.23.4-.02.04-.05.08-.07.12-.02.02-.05.05-.07.09-.05.04-.07.06-.07.06v-.1s.16-.24.16-.24c.03-.06.05-.12.08-.19.03-.08.06-.16.08-.22l.11-.18s.05-.07,0-.1c-.02,0-.03,0-.03,0,0-.02,0-.03,0-.03l.15-.24v-.03s-.03,0-.03,0l-.07.09-.03.03v-.06s.08-.14.16-.31l.57-.98.43-.86c.05-.06.09-.14.12-.25.05-.12.09-.22.12-.28.15-.24.25-.44.31-.58.05-.1.12-.21.19-.34.1-.14.16-.26.19-.37.25-.41.43-.71.53-.92.17-.28.32-.55.42-.8.03-.13.09-.25.16-.37.1-.14.16-.24.19-.31l.54-1.05.34-.55s.05-.08.07-.12c.03-.06.04-.12.05-.19.25-.41.4-.71.47-.92l.15-.28c.03-.06.07-.13.12-.21.05-.1.09-.21.12-.31l.46-.83c.05-.12.2-.36.45-.7.08-.21.13-.32.16-.34.05-.06.03-.09-.06-.1l-.26-.02c-.43,0-.76.02-1,.04-.34.01-.62.03-.84.06-.32,0-.72.04-1.2.15-.26.04-.49.1-.69.16-.2.05-.36.09-.49.12l-1.08.26s-.05.04-.07.06c-.17-.01-.34.01-.52.08-.16.07-.28.13-.37.16-.18.11-.32.19-.4.22-.05.04-.07.06-.07.06-.02.02-.06.03-.1.02.02,0,.03-.02.04-.06l.31-.23.47-.28s.06-.04.1-.06c.04-.02.07-.04.07-.06l.24-.17.03-.03.57-.3.13-.05s.06-.02.1-.06c.02,0,.03,0,.03,0,0-.02,0-.03,0-.03h.06s.09,0,.13-.02c.05-.04.09-.07.14-.08v-.03s-.03,0-.03,0h-.29s-.06-.03-.06-.03v-.06s.41-.25.41-.25l.04-.06.27-.11v-.03s-.03,0-.03,0h-.06s0,0,0,.03c0,0-.01,0-.03,0l-.1.06s-.01,0-.03,0c0,0,0-.01,0-.03-.04,0-.06,0-.06,0l-.36.07s-.1.02-.16.02h-.03s.04-.06.04-.06l.13-.02.1-.09.03-.03c.11-.03.28-.1.5-.21h.03c.09.01.15,0,.19-.01.05-.04.18-.07.39-.09l.1-.02s.05-.06.07-.06c.06,0,.13,0,.19-.02.07-.04.14-.05.23-.04h.03s.06,0,.06,0c.02-.02.05-.03.07-.03.04,0,.08,0,.1-.02.02,0,.07-.03.14-.08.05-.04.08-.05.1-.02,0,.02,0,.03,0,.03.02,0,.03,0,.03-.03l.1-.09s0-.03-.03-.03h-.26s-.81.1-.81.1c-.02,0-.08.01-.17.05h-.03s.03-.03.03-.03l.16-.05.04-.06s-.05.03-.07.03h-.1s-.05-.04-.09-.05l-.52.08h-.03s.03-.03.03-.03l.39-.09.36-.03.03-.03h-.03s-.04,0-.06,0c0-.02,0-.02-.03,0-.06,0-.12,0-.16.02h-.06s.07-.03.07-.03c.22-.07.38-.11.49-.12l.07-.03h-.06c-.11-.01-.19-.01-.26,0-.07.02-.14.02-.23.01-.08,0-.15,0-.19.02-.07.02-.16.02-.29,0v-.03s.43-.06.43-.06c.02-.02.05-.03.07-.03.04,0,.08,0,.1-.02.16-.07.36-.13.63-.17.39-.07.63-.12.72-.13.02,0,.03,0,.03-.03h-.06c-.07.01-.16.03-.3.07-.11.01-.21,0-.32-.03-.02-.02-.04-.02-.06,0,0,0-.01,0-.03,0l.1-.06.13-.05c.18-.07.37-.11.59-.11.22-.02.36-.04.42-.06l.39-.06.1-.02c.09-.04.16-.05.23-.04.26-.04.41-.07.46-.09l.16-.02h.16s.06.02.06.02l.1-.02-.09-.04-.41-.1-.03.03.03-.03.41.04.19.02.03-.03s.07-.06.13-.05c.11-.03.27-.06.49-.09l.55-.02c.22-.05.54-.09.98-.14.13-.03.37-.05.71-.07.11-.03.25-.05.42-.06.17-.03.3-.05.39-.06.37-.05.69-.08.97-.08.13-.01.25-.02.36-.03.13-.03.26-.05.39-.06.11,0,.22,0,.35,0,.13-.03.26-.04.39-.03l.41.07c.08.03.18.04.29.02l.19.08.15.08h.06c.08.08.18.13.31.16.13.03.21.05.25.05.04,0,.16.05.34.13.19.08.33.19.42.33.05.11.21.3.47.55.08.05.15.11.21.18.06.07.12.13.18.18,0,.02.02.05.06.1.06.07.08.15.08.23v.13c-.02.06-.05.08-.11.06-.02-.02-.05,0-.1.06-.05.04-.07.08-.07.12s-.02.08-.04.12c0,.04,0,.09.02.13.05.13.08.23.07.3,0,.08,0,.15.02.19,0,.02.02.13.07.33,0,.06-.06.09-.17.08l-.43-.23c-.06,0-.12,0-.16.02-.06,0-.09-.02-.09-.04-.24-.21-.45-.35-.64-.41-.08-.05-.24-.09-.47-.11-.23-.04-.5-.04-.8,0-.3.02-.52.03-.65.04l-1.07.13-.58.08h-.1s.06.06.06.06l.08.2s.06.07.06.07c.14.16.15.32.05.49l.03.03c.02.07,0,.12-.05.16-.04.02-.08.04-.1.06,0,.02-.01.03-.03.03-.02,0-.03,0-.03,0l-.21-.15h-.1s-.03.01-.04.05c-.05.06-.15.1-.3.13-.02,0-.07.03-.14.08-.03.04-.14.2-.33.49-.16.16-.33.4-.51.73l-.57,1.04-.56.88-.45.73c-.11.23-.21.43-.31.62-.1.16-.19.32-.26.46-.25.39-.39.62-.41.7-.02.04-.05.09-.08.15-.03.06-.05.12-.08.19l-.22.33c-.1.18-.17.31-.19.37l-.23.43-.34.61-.44.67c-.1.18-.2.35-.3.49-.08.14-.15.28-.23.4l-.59.88c-.13.29-.27.53-.42.73-.2.37-.35.64-.43.83-.03.06-.06.15-.09.25-.03.08-.08.19-.16.31-.05.1-.12.21-.19.34-.08.14-.15.29-.23.43l-.75,1.22-.2.5-.27.55c-.19.43-.29.75-.31.94l-.12.99.02.52s-.01.03-.03.03v-.03s0-.01,0-.03c0,0-.01,0-.03.03v-.03s-.03,0-.03.03l-.04.06-.03-.07ZM36.47,44.14c.1-.16.16-.29.19-.37l.07-.03c-.05.06-.12.19-.23.4l-.04.06v-.06ZM36.73,43.74c0-.06,0-.11-.02-.13l.04-.06.03.07-.04.12ZM37.96,41.5l.11-.12-.03-.07s-.01.03-.03.03l-.08.15v.03s.03-.03.03-.03ZM36.28,29.41s.07-.02.07-.06c.06,0,.11,0,.13-.02h.03s.24-.17.24-.17c.07-.06.18-.08.33-.07l.06.04h-.06s-.17.08-.17.08c-.03.06-.07.09-.14.08-.04,0-.1.02-.17.08l-.23.04s-.05.03-.07.03c0-.02,0-.03-.03-.03ZM37.67,28.85s.08-.06.1-.06l-.03-.03-.1.06.03.03ZM38.05,27.83h.03s.26-.04.26-.04h.03s-.03.03-.03.03c-.07.02-.15.02-.26,0h-.03ZM50.5,43.56c-.25-.02-.45-.05-.57-.08-.04,0-.15-.03-.31-.09l-.12-.04-.43-.2-.34-.13-.3-.22s-.09-.07-.15-.08c-.04-.02-.1-.05-.19-.08-.08-.05-.14-.11-.18-.18l-.32-.7c-.04-.07-.08-.08-.12-.04-.02.02-.05.03-.07.03,0-.02,0-.03-.03-.03l-.07-.33-.09-.07-.15-.53-.04-.32-.05-.49c0-.39,0-.69.01-.9-.01-.11,0-.29.02-.54.02-.19.04-.34.07-.44v-.06s0-.26,0-.26c0-.06.04-.18.09-.35,0-.02.01-.04.04-.06.02-.02.04-.05.04-.09l.05-.16s0-.01,0-.03c0-.02,0-.02-.03,0v-.06s.07-.06.08-.12c.02-.21.08-.49.2-.82.1-.44.15-.67.16-.69v-.06s0-.32,0-.32v-.1c.02-.08.07-.14.18-.18l.03-.03c0-.11.04-.26.11-.47,0-.02.02-.07.05-.16.03-.1.09-.18.18-.24l.07-.03c.07-.02.11-.04.14-.08.03-.04.04-.07.04-.09l.07-.12.24-.59.08-.15c.05-.08.09-.16.12-.25.05-.08.11-.17.18-.27l.2-.46.19-.34c.05-.06.1-.15.15-.28.11-.23.24-.46.41-.7.05-.08.16-.27.34-.58.03-.08.09-.21.19-.37.05-.08.09-.16.12-.25.05-.08.11-.17.18-.27.12-.16.25-.29.39-.38.09-.08.16-.13.21-.14.12-.1.23-.15.34-.16.04-.02.12-.04.23-.08.11-.03.21-.06.3-.07l.19.02c.19.02.36.06.5.14h.1c.13.02.22.08.27.19,0,.04.02.07.06.07.15.01.23.05.25.12.02.04.04.11.08.2.06.07.07.15.04.23l-.05.22c-.02.19-.04.34-.07.44l-.02.26-.04.06c-.13.01-.17.07-.11.18.04.09.04.17,0,.26-.02,0-.03,0-.03.03l-.03-.03-.03-.07s-.06.03-.1.02c-.02,0-.04,0-.07.03v.1c-.04.17-.14.4-.29.68-.03.06-.07.13-.12.21-.05.06-.09.12-.11.18l-.23.4c-.13.27-.22.43-.27.49l-.09.25v.03s.03,0,.03-.03c0,0,.02-.02.07-.06l.02.1s.03.1-.01.16c-.03.04-.04.07-.04.09,0,0,0,.01,0,.03,0,0-.01,0-.03,0-.15.03-.24.11-.28.23,0,.04-.04.08-.11.12-.05.04-.05.09-.01.16.02.02.02.07-.01.13-.02.02-.04.05-.04.09s-.02.07-.04.09c-.02.04-.05.09-.08.15-.02.04-.05.09-.08.15l-.24.53-.17.53c-.1.21-.17.36-.2.46l-.04.06c-.07.08-.14.22-.2.43l-.13.34c-.17.44-.27.74-.3.91-.03.13-.07.27-.1.44-.03.15-.06.34-.08.57-.09.55-.07,1.02.07,1.42.02.02.03.05.03.07.02.02.06.04.12.04l.39-.09s.1-.04.16-.02c.04.02.11.02.19-.02l.3-.07c.09-.04.22-.11.4-.22.11-.05.22-.14.31-.26.12-.12.2-.2.25-.24.04,0,.04-.02,0-.06-.02-.02,0-.05.04-.09.14-.12.23-.22.28-.3.09-.1.19-.2.28-.3.12-.12.24-.25.35-.39.07-.12.21-.28.4-.48l.21-.24.14-.18.21-.21.14-.18s.05-.09.08-.15c.05-.06.07-.12.08-.19l.07-.12v-.1s-.03-.02-.06,0c0,0-.01,0-.03,0v-.03s.11-.12.11-.12c.05-.04.05-.07,0-.1-.02-.04-.03-.08-.02-.1,0-.02,0-.03-.03-.03,0,0,0,.01,0,.03,0,0-.01,0-.03,0,.02,0,.03,0,.03,0,0-.02,0-.03,0-.03.12-.2.19-.34.2-.4,0,0,.03-.03.1-.09,0,0,.02,0,.06,0,0,.04-.02.06-.04.06-.02.02-.04.05-.04.09,0,.04-.02.07-.04.09v.03s.03,0,.03,0c0-.02,0-.03,0-.03l.14-.15.33-.42s.03-.07.08-.15l.14-.15s.04,0,.07-.03c.02-.04.03-.07,0-.1v-.1s.11-.06.11-.06v.06s-.16.31-.16.31c-.02.02-.04.05-.04.09v.03s.03-.03.03-.03l.31-.29c.17-.24.27-.38.29-.42.07-.1.13-.19.18-.27.05-.08.1-.15.15-.21.1-.12.22-.3.37-.55l.12-.21.11-.15.26-.43.34-.55.23-.4c.03-.08.09-.18.19-.3l.26-.46.2-.5.1-.38.23-.46.3-.49.15-.24v-.06s.01-.1.01-.1c.06-.17.11-.29.16-.37.14-.18.22-.27.22-.27.03-.04.07-.1.14-.18.09-.1.15-.17.18-.21l.48-.73c.15-.2.27-.38.37-.55.03-.08.09-.17.18-.27.09-.1.17-.2.22-.3l.07-.03s.08,0,.1-.02c.03-.06.07-.06.13.01.04.02.04.06,0,.1-.03.08-.08.18-.15.28-.07.1-.12.18-.15.24l-.12.25.03.03.03-.03.04-.06v.1s-.02.02-.05.06c0,.02.02.03.06.04.02,0,.03.01.03.03-.02.02-.04.05-.04.09.02.02.02.04,0,.06l-.04.06s0,.1-.01.16c0,.06-.02.13-.05.19-.05.08-.1.18-.16.31-.1.18-.16.3-.19.34-.05.1-.1.22-.16.34,0,.04-.02.06-.04.06-.07.02-.08.07-.05.16,0,.08-.03.15-.08.19l-.11.15s0,.04.03.07c.02,0,.03,0,.03,0,.02-.02.03-.02.03,0,.02,0,.02.01,0,.03l-.08.15c-.05.12-.08.21-.09.25l.03.07.04-.06.22-.33h.03s.03.02.03.04c0,.06-.04.16-.09.28l-.07.09s-.07.06-.07.06c.02,0,.03.03.02.1v.06s.01.02.05.07l-.03-.07s.05-.05.07-.09c.03-.06.06-.09.1-.09l.04-.06s.06,0,.06,0v.03s.06-.02.06,0c.02.02.02.04,0,.06,0,.04-.02.12-.05.22-.03.1-.07.19-.12.25-.02.04-.04.1-.05.19v.03s.05,0,.03.03c0,0-.01.02-.04.06,0,.04,0,.08.02.1l-.04.06s-.04.05-.04.09c0,.02-.01.04-.04.06v.1s0-.03.03-.03c.04-.02.07-.04.07-.06v-.03s0,.03,0,.03v.03s-.07.09-.08.15c0,.06,0,.11-.01.13l.05.13v.06s-.05.12-.05.12l.03.07s0-.03,0-.03c.02,0,.03,0,.03,0l.15-.24.07-.03.02.1-.04.09s.07-.07.07-.09c.02-.04.05-.08.07-.12.03-.04.06-.08.11-.12l.14-.12.22-.27s.02-.02.07-.06v.06c-.11.16-.16.3-.17.4l-.15.21c-.1.18-.17.3-.19.34-.05.08-.18.31-.38.67l-.23.46-.22.27c-.03.06-.09.15-.18.27-.16.33-.28.56-.38.71v.03s.03,0,.03,0l.15-.24c.03-.08.11-.18.25-.3.16-.16.31-.36.44-.6l.23-.43c.03-.08.09-.18.19-.3l.26-.43.21-.24.15-.24s.03,0,.03,0c0-.02,0-.03,0-.03.05-.04.07-.06.07-.06l-.04.06c-.03.06-.07.13-.12.21-.03.06-.05.12-.08.19-.03.08-.08.18-.15.28-.07.1-.12.18-.15.24l-.22.33c-.03.06-.09.15-.18.27-.1.21-.19.36-.26.46l-.12.21c0,.06-.02.12-.05.16l.03.03s.03,0,.03-.03l.18-.27c.07-.1.11-.18.12-.25.02-.02.03-.02.03,0h.06s.07-.02.07-.02c-.05.04-.07.06-.07.06-.1.18-.28.46-.52.82-.07.1-.13.19-.18.27-.03.08-.07.17-.12.25l-.34.55-.03.03c-.07.06-.1.09-.1.09l-.45.8c-.05.08-.1.15-.15.21-.05.06-.08.11-.11.15,0,.08-.02.14-.05.16l-.15.24c-.1.12-.15.21-.15.28,0,.04-.04.09-.11.15-.1.12-.16.21-.18.27-.07.1-.16.22-.26.36-.08.14-.16.29-.26.43-.03.06-.09.15-.18.27-.09.08-.24.26-.43.54-.02.02-.04.05-.04.09,0,.02-.01.04-.04.06v.06s-.01.1-.01.1c-.03.06,0,.1.06.1l.03.03s0,.01,0,.03c0,0-.01,0-.03,0l-.24.17c-.05.08-.08.14-.08.19,0,.02-.04.08-.11.18-.05.1-.04.21.04.32v.03s-.07,0-.07,0c-.08-.03-.16,0-.23.08-.05.04-.07.06-.07.06l-.5.53-.36.42-.32.36c-.12.16-.32.38-.6.65l-.34.23-.38.26s-.06.05-.17.15l-.07.03c-.05.1-.13.17-.24.2-.09.01-.14.03-.17.05l-.27.14-.2.08c-.31.08-.5.14-.59.17-.13.07-.34.12-.62.14-.19.03-.49.04-.87.05ZM55.09,42.54s-.06,0-.06,0l-.21-.15s-.04-.02,0-.06h.03s.04.04.06.04c.04-.02.08-.03.1-.02h.03s-.02.04,0,.07l.06.1v.03ZM55.37,39.32l.07-.06c.15-.03.21-.11.18-.24v-.03s-.06,0-.06.03l-.19.31s0,.01,0,.03v-.03ZM55.69,38.96s.07.03.1,0l.28-.3s.05-.07,0-.1c0-.02,0-.03-.03-.03h.06s.02.05.06.01l.15-.21v-.03c-.06-.07-.03-.1.07-.09.02,0,.03,0,.03-.03l.11-.15s.05-.06,0-.06c-.02,0-.03,0-.03,0,0-.02,0-.03,0-.03h.03s.06,0,.06,0c0-.02.01-.03.03-.03l.04-.09s.05-.06,0-.06v-.03s.08.02.1-.02c.03-.04.04-.07.04-.09l-.06-.1-.03.03-.29.39c-.14.16-.24.28-.29.36l-.21.24c-.05.08-.15.2-.29.36,0,.04,0,.06.03.07ZM55.78,36.76s0-.03-.03-.03c0-.02.01-.04.04-.06l.07-.06v.03s-.08.12-.08.12ZM56.98,37.44s-.05-.04-.09-.04c0,0-.01,0-.03.03-.02,0-.02,0,0,.03l.06.07.07-.09ZM56.36,36.45c-.08,0-.09-.04-.02-.1v-.03s-.03.03-.03.03l-.07.12v.03s.03.01.03.03c.02,0,.04,0,.07-.03l.04-.06ZM57.31,36.95v-.03s0-.03,0-.03l-.03.03-.03.03s-.07,0-.1.06c0,.06-.02.11-.04.12,0,.02-.02.05-.04.09,0,.02-.01.03-.03.03-.08,0-.1.02-.04.09,0,.02,0,.03,0,.03.02,0,.03,0,.03-.03l.29-.39ZM55.76,35.6l.22-.37s.03,0,.03,0c0-.02,0-.03,0-.03h-.06s-.07.12-.07.12c-.05.04-.1.12-.15.24v.03s.03,0,.03,0ZM56.41,36.26l.11-.12s.01,0,.03-.03c.03-.04.05-.05.07-.03l.04-.06s-.02,0-.06,0c-.02-.02-.03-.02-.03,0l-.18.21v.06s.03-.03.03-.03ZM57.35,36.86s.03,0,.03-.03l.11-.15s0-.03-.03-.03l-.11.15v.06ZM56.05,35.14l.11-.18v-.03s-.03,0-.03.03l-.11.15v.03s.03,0,.03,0ZM52.82,40.16l.27-.2.24-.2.07-.06s.05,0,.1-.02c.04-.02.06-.06.04-.12l.14-.12s.07-.02.07-.06c.02-.02.05-.06.07-.12.05-.06.1-.1.17-.11l.04-.06s.04-.06.11-.12c.05-.04.07-.08.07-.12,0-.02.01-.03.03-.03.12-.1.17-.15.17-.15.02-.02.04-.04.04-.06,0-.02.01-.03.03-.03l.03-.03.11-.15s.09-.09.14-.15c.05-.08.11-.16.18-.24.02-.02.02-.04,0-.06,0-.02,0-.04,0-.06.04,0,.08,0,.1-.02.14-.16.24-.28.29-.36.05-.04.17-.2.36-.48l.33-.42.37-.55.4-.58.55-.79.12-.21s0-.05-.03-.03l-.06-.04s.08-.06.1-.06c.04.02.07,0,.1-.06l.07-.12s.02-.03,0-.03c0-.02,0-.03-.03-.03h-.03s0-.03,0-.03c.02,0,.03,0,.03,0l.07-.03h-.06s-.06-.04-.06-.04h.06s.06.01.06.01c.02.02.03.03.03.03.02-.02.04-.04.04-.06l.22-.33c.07-.08.12-.15.15-.21.03-.08.06-.15.08-.19.02-.04.11-.17.26-.4.05-.08.04-.12-.02-.13-.02,0-.03-.02-.03-.07h.03s.07.06.09.04c.05-.04.09-.1.14-.18.02-.04,0-.09-.05-.13h-.06s.07-.03.07-.03h.03s.03,0,.03,0c0,0,0,.01,0,.03,0,0,.01,0,.03,0,.02,0,.03,0,.03-.03l.15-.24c0-.08.02-.14.05-.16,0-.02.01-.04.04-.06.02-.02.05-.04.07-.06.05-.08.04-.12-.02-.13-.11,0-.12-.04-.06-.1l.07-.03s0,.01,0,.03c0,0,.01,0,.03,0l.02.1.04-.06-.03-.07-.03-.07v-.03s.03,0,.03,0c.04.02.07.04.09.04.02,0,.03-.02.04-.06l.04-.06h-.06s-.06-.02-.06-.04v-.06s.22-.27.22-.27l-.02-.1s0-.03,0-.03c.02,0,.03,0,.03,0,.02,0,.04,0,.07-.03.05-.04.07-.07.07-.09,0-.02,0-.03-.03-.03,0-.02,0-.03-.03-.03l.03-.03c.06,0,.11-.02.14-.08.02-.02.04-.04.04-.06.02-.04.05-.06.07-.06v-.03s-.03-.03-.09-.04l.04-.12v-.06s0,0-.03,0c0,0,0,.01,0,.03-.05.04-.07.07-.07.09-.02.02-.04.05-.04.09l.1-.02v.06s-.04,0-.04.03c0,.02-.03.05-.07.09v-.1s-.02-.03-.02-.03l-.03.03-.04.06c-.07.08-.16.2-.26.36l-.19.3-.18.24s-.04.05-.04.09c0,.02-.01.04-.04.06-.02.02-.05.05-.07.09-.02.04-.05.07-.07.09,0,.02-.02.05-.04.09,0,.02,0,.04.03.07h.03s0,.03,0,.03h-.03c-.02-.07-.05-.07-.1-.01l-.08.15s-.08.09-.11.15c-.02.04-.05.08-.07.12l-.12.28-.15.21-.07.12c-.05.06-.1.13-.15.21-.03.06-.06.12-.11.18,0,.02-.02.05-.04.09,0,.02-.03.05-.07.09-.02.02-.05.05-.07.09-.02.04-.04.07-.04.09l-.04.09s-.07.05-.07.09c0,.02,0,.04,0,.06,0,.02-.03.04-.07.06-.02,0-.02.02,0,.06,0,.02-.04.06-.11.12,0,.02-.03.05-.07.09v.06s-.22.24-.22.24c-.02.02-.04.05-.04.09.02.02.02.04,0,.06.04.05.04.07,0,.06-.04,0-.06,0-.06,0l-.03.03-.11.18c0,.08-.02.14-.05.16-.09.08-.15.15-.18.21-.1.12-.16.22-.19.3-.03.08-.08.15-.15.21l-.08.15s-.03,0-.03.03c-.02,0-.04,0-.07.03,0,.02,0,.04.03.07,0,0,0,.01,0,.03,0,0-.01,0-.03,0,0,0-.01,0-.03,0,0,.04-.02.07-.04.09-.02.02-.05.04-.07.06-.02.02-.04.05-.04.09,0,.02-.04.09-.12.21-.07.12-.12.19-.15.21,0,.02-.01.04-.04.06-.02,0-.03.02-.04.06l-.1.09s0,.1-.08.15c-.02.04-.04.07-.04.09.02,0,.05,0,.1,0,.04.02.06,0,.07-.06h.03s.01.09-.01.13c0,.02-.02.04-.07.06-.02.02-.06,0-.12-.04l-.06-.04-.07.12v.03c.06.03.09.07.08.14v.06s-.04,0-.04,0l-.03-.07v-.06s-.09,0-.09,0l-.03.03.06.07.06.04s-.06.04-.04.06c.02.02.04.04.06.04h-.03s-.05,0-.1.02c-.04.02-.06.06-.04.12h-.03s0-.07,0-.07l-.06-.04v.03s.01.09-.01.13c-.02.04-.04.08-.04.12,0,0,0,.01,0,.03,0,0-.01,0-.03,0v-.03s0-.06-.06-.07c-.02-.02-.04-.02-.06,0,0,.02,0,.04.03.07,0,0-.01,0-.03,0,0,0,0,.01,0,.03l-.1.09c-.09.08-.14.16-.15.24-.02.02-.06.04-.1.06-.02.02-.03.05,0,.1,0,.08-.04.11-.1.09h-.06s.03.03.03.03l.03.03s.03.01.03.03v.03s-.16-.01-.16-.01c0,.02-.02.03-.07.03,0,.06-.03.1-.07.12l-.04.09-.31.26-.36.42-.31.29s-.01,0-.03,0c0,0,0,.01,0,.03h.06s.03-.02.03-.02ZM56.69,35.97l.07-.06v-.03s-.03,0-.03,0h-.03s0-.03,0-.03l.04-.06.17-.08v-.03s0,0-.03,0t0,0h-.03s0-.07,0-.07h.06s.06,0,.07-.02l-.03-.07s-.05,0-.1.02c-.02.02-.02.04,0,.06l-.03.03-.18.21v.13s.02-.02.02,0c.02,0,.03.01.03.03v-.03ZM57.57,36.53l.14-.15v-.03s-.03,0-.03,0l-.11.18s0,.01,0,.03v-.03ZM56.21,34.83s.03,0,.03-.03l.14-.15s0-.01,0-.03c.03-.04.02-.06-.03-.07v-.03s0-.06,0-.06l-.04.06s-.02.07-.04.09h.03s-.11.19-.11.19v.03ZM57.06,35.42l.08-.15v-.03s-.01.03-.03.03l-.07.12s-.03,0-.03.03c.02,0,.03,0,.03,0h.03ZM57.79,36.22c.05-.08.1-.14.14-.18h-.03s-.14.15-.14.15v.03s.03,0,.03,0ZM56.96,35.03s-.01,0-.03,0l.07-.06.06.04s-.06.03-.1.02ZM57.06,35.42l.14-.18c0-.06,0-.12-.02-.16l.07-.06.07-.03.07-.03s-.02-.05-.06-.1c0,0-.01,0-.03,0,0,0,0,.01,0,.03-.05.08-.08.14-.08.19l-.07.03c-.03.06-.05.11-.08.15-.02.02-.05.04-.07.06l-.07.09h.1s.03.01.03.01ZM56.65,34.58l.14-.18s0-.03-.03-.03l-.15.21s.03.01.03.03v-.03ZM57.58,35.72s.05-.08.07-.12c.02-.04.06-.08.11-.12,0-.04.02-.06.04-.06,0-.02,0-.03-.03-.03,0,0-.01,0-.03,0,0,0,0,.01,0,.03l-.18.27v.03s.03,0,.03,0ZM57.46,34.81s-.05-.05-.03-.07c.02-.04.04-.07.04-.09v-.03s-.03.03-.03.03l-.04.06-.07.09.12.04v-.03ZM56.64,34.33l.08-.19.22-.27.15-.24v-.1s-.06.03-.06.03l-.15.24-.04.06h.03s-.07.06-.07.06l-.22.37s0,.02,0,.06l.07-.03ZM56.91,34.16s0-.03,0-.03c.02,0,.03,0,.03,0l.07-.09.15-.24s0-.03-.03-.03v.03s-.11.12-.11.12l-.11.18v.06ZM57.72,34.42s-.01,0-.03,0c0,0,0,.01,0,.03h-.06s0-.04,0-.04c0,.02-.01.03-.03.03.02.02.05.04.09.04l.04-.06ZM57.73,34.39s.07-.07.07-.09c0-.04-.02-.07-.06-.07-.02,0-.04,0-.07.03,0,0,0,.01.03.03l.02.1ZM57.21,33.7l.22-.3s.01-.03.03-.03l-.03-.03h-.03c-.1.16-.16.28-.19.37-.02,0-.03,0-.03.03.02,0,.03,0,.03,0v-.03ZM57.2,33.44s.05-.08.07-.12c.03-.06.05-.12.08-.19v-.06s-.02.03-.06.03v.03c-.05.06-.1.15-.16.28-.02.02-.04.04-.04.06.02,0,.03.01.03.03h.03s.04-.06.04-.06ZM58.15,35s.09-.1.14-.18c.1-.16.19-.28.26-.36.05-.08.1-.15.15-.21.05-.08.09-.14.11-.18v-.06s-.06.03-.06.03l-.11.18s-.12.18-.29.42l-.12.21-.11.12v.06s.03,0,.03,0v-.03ZM58.02,33.93v-.03s-.04-.06.01-.1c0-.02,0-.03-.03-.03-.05.08-.1.14-.14.18,0,.02,0,.03,0,.03.02,0,.03,0,.03,0l.13-.05ZM57.61,33.09h-.03s-.07.09-.07.09l.03.07.08-.15ZM57.62,33.03s.03,0,.03,0c0-.02,0-.03,0-.03.05-.08.1-.14.14-.18,0-.02,0-.03-.03-.03h-.03s-.12.21-.12.21v.03ZM57.46,32.98c0-.06.02-.09.04-.09.07-.06.12-.13.15-.21l.07-.12s.06-.05.11-.15c-.02,0-.03,0-.03,0,0-.02,0-.03,0-.03-.04,0-.08,0-.1.02-.03.13-.1.24-.19.34l-.11.21v.06s.06-.03.06-.03ZM58.09,33.2l.03-.03.03.07s0,.02-.04.06l-.02-.1ZM58.4,33.23s.04.03.06,0c-.04-.05-.06-.07-.06-.07,0,0-.02.02-.07.06h.06ZM57.88,32.67l.12-.21h-.03s-.11.18-.11.18v.03s.03,0,.03,0ZM58.93,33.85s.03,0,.03-.03l.18-.27s.01-.03.03-.03c0-.02,0-.03-.03-.03l-.07.03-.04.09-.11.21v.03ZM59.26,33.37l-.03-.07s-.03.08-.07.12l.03.03.07-.09ZM58.71,33.03s0-.03,0-.03c.02,0,.03,0,.03,0l.11-.15.04-.06s0-.08-.02-.1c0,.04-.02.06-.04.06v.06s-.12.18-.12.18v.03ZM58.1,32.27l.22-.33-.03-.07s-.01.03-.03.03l-.19.3v.1s-.01.03-.01.03l.04-.06ZM59.01,33.31l.22-.27c.05-.1.1-.17.15-.21l-.03-.03h-.03s-.07.09-.07.09l-.08.15s0,.01,0,.03c0,0-.01,0-.03,0l-.15.24s-.03,0-.03.03c.02,0,.03,0,.03,0l.03-.03ZM57.87,32.31l.07-.12.23-.4.03-.03v-.1c.05,0,.07,0,.07-.03.02-.02.04-.04.04-.06l.07-.12.11-.21s.04-.08.04-.12c.03-.06.06-.1.11-.12v-.06s-.02-.07-.02-.07l-.04.06-.07.09s-.05.08-.07.12c-.02.04-.04.09-.05.16l-.15.21-.07.12c-.03.06-.02.12.02.16-.04-.05-.08-.05-.13-.01-.1.16-.16.29-.19.37-.02.02-.04.05-.04.09,0,.02-.01.04-.04.06l.03.07.04-.06ZM59,32.64s.04-.1.05-.19c.1-.12.16-.21.18-.27v-.03s0,0-.03,0v.03s-.12.18-.12.18v.1s-.15.15-.15.15c0,0,0,.02,0,.06l.07-.03ZM58.88,32.14c-.08-.05-.13-.08-.15-.08v-.03s.1,0,.1,0l.03.03v-.03s.04-.06.04-.06c0,.02,0,.03,0,.03.02,0,.03,0,.03,0-.02.02-.04.06-.04.12ZM58.37,31.81l.26-.43s.04-.05.04-.09c-.05.04-.07.06-.07.06,0,.02-.01.03-.03.03l-.23.4v.06s.03-.03.03-.03ZM59.09,32l.11-.18.11-.15v-.06s-.03.03-.03.03c-.1.16-.16.29-.19.37v.03s0-.03,0-.03ZM59.08,31.39h.06s.06.07.06.07h-.03s-.04-.03-.06,0c0,0-.01,0-.03,0v-.06ZM59.15,30.98s.07-.07.07-.09l.03-.03h-.03s-.07.08-.07.12ZM59.4,30.62l-.03-.03-.08.15h.03s.07-.12.07-.12ZM59.67,30.83l-.03-.03-.1.09.06.07.07-.12ZM61.02,32.3h.03s0,.03,0,.03l-.11.15.08-.19ZM58.74,30.81s.03,0,.03-.03l.04-.09c.07-.12.11-.19.12-.21,0-.06.03-.14.08-.22.15-.2.24-.35.3-.46l.22-.33.04-.06-.03-.03h-.03s-.12.21-.12.21l-.11.18-.48.76-.12.25.06.04ZM60.4,31.7s0-.03,0-.03c.02,0,.03,0,.03,0l.09-.25-.03-.03s-.01,0-.03,0c0,0,0,.01,0,.03l-.04.12s0,.01,0,.03c.02.02,0,.02-.03,0v.03s.02.1.02.1ZM59.51,30.43l.26-.4.07-.09v-.03s-.06.03-.06.03l-.3.49-.07.12.11-.12ZM60.15,30.84l.11-.18v-.03s-.03,0-.03,0l-.12.21s.03.01.03.03v-.03ZM59.92,29.79s.03,0,.03-.03l.04-.12v-.03s-.03,0-.03,0c0,.04-.03.08-.07.12l.03.07ZM60.3,30.24l.11-.18s.01-.03.03-.03l-.03-.03s-.01,0-.03,0c0,0,0,.01,0,.03l-.15.21.03.03.03-.03ZM60.15,29.46h-.03s-.1.08-.1.08h.03s.1-.08.1-.08ZM60.12,29.39c.07-.06.1-.09.1-.09.15-.22.23-.35.26-.4l.07-.12s0-.03-.03-.03c0-.02,0-.02-.03,0l-.04.06-.3.46-.04.12ZM59.62,29.19s.01-.03.03-.03l.44-.67c-.05.08-.08.15-.08.22,0,0,0,.01,0,.03,0,0-.01,0-.03,0l.07-.03.04-.09.07-.09.07-.03-.09-.04s-.01.03-.03.03l.23-.4.07-.03h.06s-.03-.03-.03-.03c-.02-.04,0-.06.04-.06l.04-.06-.03-.07s-.07.06-.07.06l-.04.06c-.07.04-.16.16-.29.36-.05.12-.1.22-.15.28-.02.02-.04.05-.04.09,0,.02-.01.04-.04.06l-.26.43s0,.01,0,.03l.03-.03ZM61.81,30.6s.09-.1.14-.18v-.03s0,.03,0,.03l-.11.18h-.03ZM61.59,30.16l.12-.25h.03s-.12.25-.12.25c0,0-.01,0-.03,0,0,0,0,.01,0,.03v-.03ZM60.58,27.79s.02-.02.07-.06l-.06-.04-.04.06.03.03ZM60.73,27.58s.05-.03.07-.03c.02,0,.03,0,.03-.03l.02-.19v-.03s-.03,0-.03,0l-.11.21.03.07ZM60.89,27.21s.03,0,.03-.03c.05-.08.08-.14.08-.19l.07-.09v-.06s.04,0,.04-.03h-.06s-.02.05-.04.09c0,.04,0,.08.02.1h-.03s-.09.1-.14.18l.03.03ZM62.9,25.17s.07-.08.14-.12c.07-.06.13-.09.17-.08v.03s0,.06,0,.06l-.27.11h-.03ZM58.51,48.27s-.03-.01-.03-.03l.08-.22.17-.47.2-.46.11-.12s.06-.08.04-.12v-.03s.11-.15.11-.15v-.03s-.06-.04-.06-.04c0,0,.02-.02.07-.06.09-.01.12-.07.11-.18-.02-.02-.03-.05-.03-.07.02,0,.03,0,.03-.03.03-.04.05-.1.08-.19.05-.08.08-.15.08-.22,0-.11.05-.22.13-.34.07-.12.13-.21.15-.28.03-.06.13-.29.32-.68.02-.02.04-.06.04-.12h-.03c-.07.1-.12.16-.14.18-.07.04-.13.09-.17.15l-.11.18-.07.03s0-.01,0-.03c0,0,.01,0,.03,0,.05-.08.11-.2.19-.37.08-.16.17-.31.26-.43.1-.12.17-.22.22-.3.05-.1.09-.18.12-.25v-.06s-.06,0-.06,0h-.03s.03,0,.03,0l.05-.22s.03-.07,0-.1c0-.02,0-.04,0-.06l.02-.29.03-.03s.08-.01.1-.06l.07-.12c.03-.1.1-.26.2-.46,0-.02.03-.05.07-.09.1-.12.16-.21.18-.27,0,0,0-.02,0-.06,0,0-.01,0-.03,0v.03s-.12.18-.12.18c0,0-.01,0-.03,0,0,0,0,.01,0,.03v-.03s.09-.22.09-.22c.03-.06.05-.1.07-.12.02-.04.05-.07.07-.09v-.06s.02-.06.04-.06h.03s.08-.21.08-.21v-.06s.09-.06.11-.12c.03-.08.05-.13.08-.15v-.06s-.06.03-.06.03l-.21.21c-.05.06-.09.12-.11.18-.03.06-.05.11-.08.15,0,.04-.02.06-.04.06l-.04.06v-.06s-.03-.04-.06-.04c0,0,0,.01,0,.03-.02.02-.07.08-.14.18l-.29.39-.17.15v.03s.01.04,0,.06c0,0,0,.01,0,.03,0,0-.01,0-.03,0l-.36.42-.33.49-.25.33-.03.03v-.03c.13-.18.19-.29.19-.34l.11-.18.14-.18s.04-.05.04-.09c0,0,0-.01,0-.03v-.03s.08-.12.08-.12l.18-.21v-.03s-.03,0-.03,0l-.15.24s-.08.06-.1.06c0,.02-.01.03-.03.03v-.03c.05-.08.1-.15.15-.21.05-.08.09-.14.11-.18l.44-.6.14-.15s.1-.12.15-.24c0-.02,0-.03-.03-.03v.03s-.21.21-.21.21l-.58.72s-.09.09-.14.15c-.03.06-.07.12-.14.18l-.04.06h-.03s0-.03,0-.03l.23-.4c.05-.1.11-.18.18-.24l.15-.24.19-.31v-.03s-.03,0-.03,0c0,.06-.03.09-.07.09l-.14.15s-.03.05-.07.09l-.33.42s-.01,0-.03,0c0,0,0,.01,0,.03v-.06s.05-.09.05-.09c.05-.04.07-.09.08-.15,0-.06.02-.11.04-.12.02-.04.05-.08.07-.12.12-.16.24-.33.37-.51.15-.2.3-.41.47-.63.05-.1.15-.23.29-.39v-.06s-.07,0-.09.02l-.11.15c-.12.14-.28.35-.47.63-.02.04-.05.09-.08.15-.02.04-.06.08-.11.12l-.11.15h-.03s0-.03,0-.03l.4-.58.18-.27v-.03s0-.06,0-.06c.05-.08.1-.14.14-.18.05-.04.1-.13.15-.28.02,0,.03,0,.03,0,0-.02,0-.03,0-.03h-.06c-.09.03-.15.05-.2.04-.04.02-.09.02-.13.02-.02-.02-.04-.06-.06-.1-.06-.07-.12-.1-.19-.08-.08,0-.19-.04-.31-.09,0,0-.02,0-.06,0-.02-.02-.04-.01-.07.03,0,0-.01,0-.03,0v-.03s0-.03-.03-.03c.01-.15-.05-.21-.18-.18-.09.01-.15,0-.19-.05-.04-.07-.08-.14-.14-.21-.08-.09-.14-.18-.2-.27-.08-.11-.07-.25,0-.42.05-.12.08-.23.09-.31v-.06c-.05-.05-.06-.13,0-.26.07-.1.15-.16.24-.17.06,0,.16-.03.3-.1.16-.16.34-.22.53-.18.09,0,.17,0,.26-.04.44-.09.76-.19.96-.3.13-.07.27-.09.39-.06h.1c.17.02.45-.02.85-.11.02-.02.09-.07.21-.14.15-.27.3-.51.45-.73.15-.22.27-.42.37-.58l.44-.67.46-.89.38-.64s.12-.18.29-.42l.52-.85.3-.52.11-.12s0-.04,0-.06c.02-.02.02-.03,0-.03,0-.02-.03-.03-.09-.04-.09.01-.18.03-.29.04-.09.01-.17.04-.26.07l-.72.19-1.09.39-.07.03s-.06.07-.1.09c-.04.02-.08.04-.1.06-.07.02-.25.09-.56.21-.2.11-.32.18-.34.2l-.62.43-.07.03s.03,0,.03,0c0-.02,0-.03,0-.03l.32-.33.07-.03s0-.04,0-.06c.02-.02.02-.03,0-.03-.02-.02-.04-.03-.06,0,0,0-.01,0-.03,0-.02.02-.06.03-.1.02,0-.06.02-.09.04-.09.04-.02.07-.07.08-.15l.04-.45c0-.06,0-.11-.02-.13-.03-.11-.11-.14-.22-.08h-.06s.03,0,.03,0c0-.02,0-.03,0-.03l.17-.11s.06-.02.1-.06c0-.09.06-.12.17-.11.22-.09.37-.16.44-.22.02-.02.05-.03.07-.03.04-.02.09-.05.14-.08.09-.04.22-.11.4-.22.38-.22.67-.36.87-.41h.03s.03,0,.03,0c0-.02,0-.03,0-.03h-.03c-.34-.03-.74,0-1.2.12l-.52.08h-.03s0-.03,0-.03c.02,0,.03,0,.03,0,.09-.04.3-.09.63-.17l.2-.05.36-.07c.07-.02.11-.03.13-.05.04-.02.08-.04.1-.06.13-.07.23-.1.3-.07.04.02.08.02.13-.02l.1-.09v-.03s.05-.03.07-.03c.04,0,.08,0,.1-.02l.03.07h.03c.13-.03.25-.04.36-.03l.1-.06s.06-.07.1-.09c.04-.02.08-.03.1-.02l.07-.03-.06-.04h-.16s-.32.02-.32.02c-.04,0-.06-.02-.06-.04h.03s.11-.02.19-.01c.02-.02.06-.03.1-.02.07-.06.11-.07.13-.02h.03s.07-.09.07-.09h-.03c-.13-.01-.23-.01-.32,0h-.16s-.03-.02-.03-.02c.02,0,.03,0,.03-.03h.06s.39-.06.39-.06l.13-.02c.13-.03.22-.05.26-.04l.29-.04.42-.03s.04-.02.06,0c.02,0,.04,0,.07-.03.08,0,.14,0,.16-.05.07-.06.12-.05.16.01,0,.02,0,.03.03.03.02-.02.03-.03.03-.03.05-.04.08-.04.1,0l.13-.02.33-.07h.03s-.03,0-.03,0c-.13-.01-.21,0-.26,0h-.06s.03-.03.03-.03l.26-.07.42-.06c.09-.04.26-.06.52-.08.13-.03.31-.06.52-.08.07-.02.15-.03.26-.04.13-.01.23-.01.29,0,.24-.02.61-.03,1.13-.03.11-.01.27,0,.48,0,.38.03.73.14,1.03.31.33.14.6.28.8.42.3.2.55.4.75.61.14.14.32.37.55.69l.26.38.13.33c.03.17.06.29.1.36l.08.17c.04.09.07.2.1.33l-.11-.27-.03-.03v.03s.04.29.04.29v.03s.05.1.05.16c0,.06-.01.12-.01.16v.1s-.01.06-.02.13c0,.06,0,.12.02.16.02.04.02.13,0,.26v.03s-.03-.03-.03-.03c-.04-.05-.06-.1-.05-.17,0-.08.01-.14.01-.16v-.06s-.03.06-.03.06l-.08.57c0,.11-.09.28-.24.53-.1.21-.24.41-.41.61-.17.24-.47.56-.89.95l-.74.71-.35.32-.54.34-.17.11s-.1.03-.16.05c-.04.02-.1.06-.17.11l-.51.28c-.07.06-.19.12-.37.19-.09.04-.2.09-.34.16-.11.05-.25.12-.4.19l-.37.16c-.13.07-.34.16-.6.27l-.7.26c-.31.1-.54.17-.69.2l-1.09.29c-.11.01-.13.06-.08.15l.12.11.36.29s.1.1.17.24l.08.14.43.55.11.17.43.55.22.37c.11.18.21.32.29.41.02.02.06.04.12.04.05-.04.05-.09.01-.16-.02,0-.03,0-.03,0,0-.02,0-.03,0-.03,0,0,0,.01,0,.03.02,0,.03,0,.03-.03.04,0,.06,0,.07-.03l-.02-.1v-.06s.03.07.03.07c.04.07.07.17.1.3,0,.04,0,.08.02.1.06.07.1.16.14.27.04.09.07.16.11.2l.11.17c.15.23.25.4.31.51l.42.68.25.44.17.3v.03s-.07.06-.07.06c-.13-.01-.16.03-.11.12l.25.44.5.85s.13.19.46.65c.02.02.03.06.02.1-.04,0-.07-.02-.09-.04-.16-.12-.26-.19-.3-.22-.12-.05-.19-.1-.21-.15h-.1s-.04.08-.04.08c-.02,0-.03,0-.03.03.02.02.02.04,0,.06-.05.04-.04.09.02.16l.14.21.03.03h-.06s-.08-.14-.08-.14c-.08-.09-.26-.23-.54-.4l-.21-.12s-.05-.04-.09-.04c0,.02-.01.03-.03.03,0,.02,0,.04.03.07l.17.3v.03s-.01,0-.03,0c0,0,0-.01,0-.03l-.43-.58s-.05-.06-.15-.17c0,0-.01,0-.03,0,0,0,0-.01,0-.03,0,.04,0,.06,0,.06.05.15.12.31.22.47,0,.04,0,.08.02.1-.04-.05-.06-.07-.06-.07-.04-.05-.07-.07-.09-.07l.02.1s.07.1.08.17c.04.09.07.15.11.17.02,0,.03,0,.03,0,0,.02,0,.03,0,.03h-.03s-.07-.07-.09-.07h-.06s-.11.05-.2.04c0,0-.02-.01-.06-.04-.04,0-.06.02-.04.06l-.03.03-.06-.1s-.04-.03-.06,0c0-.02-.02-.03-.06-.04-.02-.04-.07-.09-.15-.14,0,0-.02,0-.06,0,0,.02,0,.03.03.03l.08.23v.06s-.03-.03-.03-.03l-.23-.31h-.03s0,.03,0,.03l.02.1.11.2v.03c-.06-.07-.13-.17-.2-.31-.02,0-.04-.01-.06-.04,0,0-.01,0-.03.03l-.06-.04-.13-.3c-.11-.18-.3-.45-.57-.82-.02-.04-.06-.1-.11-.17-.04-.05-.07-.1-.08-.17-.08-.09-.12-.14-.12-.14-.06-.05-.13-.14-.2-.27l-.12-.11-.34-.48-.43-.55-.7-.83-.5-.53-.44-.42-.44-.52-.26-.28-.27-.25c-.06-.03-.11-.02-.13.02l-.22.3-.58.82-.4.48-.62.85-.22.33s-.03,0-.03.03c-.01.15-.08.29-.2.43-.08.14-.17.28-.29.42l-.22.33c-.05.08-.12.17-.22.27-.07.1-.15.22-.22.37-.35.53-.59.92-.75,1.19l-.32.39c-.12.2-.27.51-.43.93l-.12.25v.03ZM58.74,46.3l.19-.3h.03s0,.03,0,.03l-.07.12-.11.15-.03.03v-.03ZM59.44,45.27l.12-.21.03.07-.11.15h-.03ZM59.47,44.92h-.03c.05-.13.11-.27.17-.44.02-.02.04-.05.04-.09,0-.04.02-.07.04-.09,0-.02.01-.03.03-.03v.06s0,.03,0,.03c0-.02.01-.03.03-.03l.07-.03-.04.06s-.03.1-.08.19c-.02.02-.04.06-.04.12l-.04.06-.11.18-.04.06v-.06ZM59.77,44.14s.02-.07.04-.09l.12-.21s.03-.1.08-.19l.03-.03v.03c-.06.21-.14.38-.24.53,0,0-.01,0-.03,0,0,0,0,.01,0,.03v-.06ZM59.88,44.28s.04-.06.04-.12c.02-.02.05-.04.07-.06.02-.04.05-.09.08-.15.02-.02.05-.04.07-.06.03-.04.05-.09.08-.15h.03s-.08.16-.08.16l-.22.27s-.03.08-.07.12ZM60.05,43.52s.02-.06.04-.06c0-.04.03-.06.07-.06,0,.04-.02.06-.04.06,0,.04-.02.06-.04.06h-.03ZM60.46,43.97l.07-.12s.04-.04.04-.06c0-.02,0-.03-.03-.03-.04,0-.08,0-.1.02,0,.06-.02.11-.04.12v.03s.02.07.02.07l.03-.03ZM60.23,43.25l.04-.06.06.07s-.02.06-.04.06l-.14.08.08-.15ZM60.47,43.46s.05-.04.07-.06c.02-.04.04-.08.04-.12.06-.15.09-.23.12-.25.02,0,.03,0,.03,0,0-.02,0-.03,0-.03-.02-.04-.01-.08,0-.1.05-.04.08-.07.1-.09v-.1s-.06.06-.06.06l-.03.03-.26.46s-.04.05-.04.09c0,.02-.01.04-.04.06l.03.07.03-.03ZM61.57,40.76s.07-.07.07-.09l-.03-.03s-.07.06-.07.06l.03.07ZM70.27,44.92s0-.03,0-.03c.02,0,.03,0,.03,0,.04.05.06.07.06.07l-.04.06-.06-.1ZM69.99,44.09l-.08-.2c.04.09.07.16.11.2h-.03ZM69.91,43.89c-.06-.07-.12-.17-.2-.31l-.28-.47v-.03s.03.01.03.03l.17.27.25.44.03.07ZM68.06,41.16s-.03-.01-.03-.03c-.06-.07-.13-.12-.21-.15-.02-.02-.03-.05-.03-.07,0-.04,0-.08-.02-.1l.1-.06s.04.05.06.07c.02.02.03.05.03.07,0,.02.02.1.08.23.02,0,.03.01.03.03ZM65.89,29.19s.09-.06.13-.05c.04,0,.07,0,.1,0,0-.02.01-.03.03-.03l-.03-.03s-.1,0-.16.02c-.04.02-.08.04-.1.06l.03.03ZM67.34,35.71c.09-.04.14-.05.16-.05l.57-.24c.44-.18.77-.32.97-.43l1.01-.49c.11-.05.2-.1.27-.14.09-.06.17-.1.24-.14l.61-.36c.32-.27.58-.46.76-.58.3-.21.59-.49.88-.86l.32-.36.04-.06s0-.05,0-.1c.03-.06.06-.12.11-.18.05-.1.05-.19,0-.26-.02,0-.03,0-.03,0,0-.02,0-.03,0-.03-.01-.09-.05-.14-.11-.17l-.4-.2-.12-.11s-.03-.05-.03-.07c0-.02,0-.03-.03-.03l-.34-.13-.28-.12-.12-.04.16-.05h.03s.03,0,.03,0h-.03s-.12-.05-.25-.06h-.29c-.15,0-.25.02-.3.08l-.03.03c-.09.01-.2.08-.34.2l-.35.35c-.23.19-.4.4-.5.63-.2.28-.32.44-.36.48-.03.04-.05.07-.07.09-.02,0-.05-.02-.09-.04l-.12-.07c-.14.12-.21.17-.21.17l-.36.84c-.14.33-.28.61-.43.83l-.22.3-.77,1.15-.14.18s-.01,0-.03.03c0,.02,0,.03.03.03,0,.04.02.04.06,0l.13-.05ZM69.41,32.22s.06,0,.07-.03c.02-.02.04-.06.04-.12.03-.06.06-.1.11-.12,0-.02,0-.03-.03-.03,0,0-.01,0-.03,0,0,0,0,.01,0,.03l-.18.21s-.01.03-.03.03l.06.04ZM75.15,33.43l.04-.09.02.13h-.06s-.01.03-.03.02l.04-.06ZM75.22,32.25s-.01,0-.03,0c0,0,0-.01,0-.03v-.23s.02.07.04.13c.02.07.02.11.02.13h-.03ZM76.34,46.83c-.11,0-.2-.06-.28-.15l-.12-.04c-.15-.01-.27-.08-.37-.19-.08-.03-.15-.08-.21-.15-.08-.07-.18-.11-.31-.12-.02.02-.07.02-.13-.01-.06-.03-.11-.04-.16-.05l-.4-.23c-.13-.2-.29-.36-.47-.46-.12-.07-.21-.11-.28-.12-.11,0-.18-.08-.21-.21-.04-.07-.16-.15-.36-.26-.16-.08-.34-.28-.53-.59-.04-.07-.12-.3-.26-.7-.03-.13-.03-.25,0-.35h-.03s.13-.35.13-.35c.06-.17.09-.28.09-.35l.09-.25s.08-.1.11-.18c.03-.08.04-.14.05-.16-.06-.07-.07-.12-.05-.17.05-.06.07-.1.07-.12.03-.15.1-.27.19-.37.08-.16.16-.36.24-.59.03-.1.11-.26.23-.46.05-.08.2-.34.45-.76.08-.21.16-.37.24-.49.08-.14.14-.27.19-.37.12-.16.23-.35.34-.58.12-.1.18-.23.2-.4l.04-.12.12-.21s.04,0,.07-.03c.02-.02.04-.04.04-.06l.07-.09c.2-.33.31-.53.34-.61.1-.14.18-.27.26-.4.08-.14.14-.26.19-.34l.3-.49c.03-.06.08-.18.16-.34.08-.16.17-.31.26-.43.12-.18.2-.34.23-.46l.24-.49c.07-.08.12-.15.15-.21.03-.08.06-.15.08-.19,0-.06.05-.16.12-.28.04-.02.06-.05.04-.09,0-.06,0-.11-.02-.13l-.18-.14s0-.04-.03-.07c0-.04.02-.07.04-.09,0-.11,0-.18-.04-.23v-.06s.02-.13.02-.13c-.03-.15.02-.23.15-.24.05-.04.12-.07.23-.11.26-.08.49-.2.67-.36.04,0,.07-.03.07-.09l.32-.71s.03-.08.01-.13c0-.04.02-.09.05-.16.02-.04.06-.11.11-.21.07-.12.16-.2.25-.24.16-.14.36-.19.59-.17.21.02.37.04.48.07.1.03.21.1.3.22.06.03.12.06.18.11.06.05.12.09.18.11.02.04.07.09.15.14.1.05.17.09.21.12l.27.25s.09.07.15.08c.22-.05.39-.1.53-.18.46-.17.9-.31,1.32-.4.31-.14.62-.25.93-.31.29-.08.51-.12.68-.1l.22.02.29.02s.07.02.16.05c.08,0,.15.04.18.11.02.02.05.04.09.04.04,0,.08.02.12.04.02.02.05.04.09.04.02,0,.03.01.03.03h-.03s-.04,0-.07.02c0,.02,0,.03,0,.03l.03.07-.03.03.02.1.22.05s.02.02.06.07c.02.02.04.06.06.1.02.02.04.07.05.13,0,.06.01.11.05.13.04.02.07.05.09.07.02,0,.05.06.08.17.04.02.07.05.09.07.04.03.07.05.09.07.08.09.09.19.04.29-.01.13-.03.22-.06.28l.02.19c.01.09,0,.17-.02.26l-.13.37-.12.21h-.06c-.04-.05-.03-.12.02-.2.02-.02.04-.05.04-.09,0-.06,0-.11-.02-.13-.02-.04-.04-.09-.05-.13-.02-.04-.07-.07-.15-.08-.02,0-.03.02-.04.06l-.04.06v-.06s-.02-.07-.02-.13l-.19-.02h-.1c-.06-.04-.15-.04-.25-.03-.31.1-.54.17-.69.2-.26.08-.66.2-1.19.35-.44.09-.75.17-.95.24-.11.03-.27.08-.49.15-.22.05-.4.07-.55.08-.07.02-.14.04-.23.08-.07.02-.14.04-.23.08-.13.03-.2.05-.2.05-.13.03-.24.04-.32.04-.02.02-.07.04-.13.05-.06,0-.1,0-.1.02l-.08.15-.31.62c-.05.08-.12.19-.22.33-.07.12-.14.24-.19.37-.12.2-.21.37-.27.49-.07.12-.16.24-.26.36-.07.12-.15.25-.23.4l-.11.15v.03s.06,0,.06,0l.4-.13c.13-.01.25,0,.35.03.04.02.17.05.38.07.06,0,.1.04.12.11.02.02.05.04.09.04.19.08.3.12.34.13v.06s-.04,0-.04,0c-.02,0-.03,0-.03.03,0,.02-.01.03-.03.03.02,0,.03.01.03.03,0,.02,0,.03.03.03l.22.05h.03s.12.11.12.11l-.13.05c-.08,0-.14,0-.16.02h-.03s0,.03.03.03l.09.04.32.03s.1.03.19.08c.03.11.08.18.14.21l.19.05c.06.03.09.06.09.1,0,.02-.01.03-.03.03l-.25-.09h-.06s.03,0,.03.03c.02.07.05.12.11.17.08.03.15.06.19.08l.26.28s0,.01,0,.03c0,0,.01,0,.03,0h-.1s0-.04-.03-.04c-.02,0-.03,0-.03,0-.01-.09-.03-.11-.06-.07-.02.02-.05.03-.07.03l.02.13.15.14s0,.01,0,.03c.02.02.04.04.06.04-.04,0-.08-.03-.12-.07h-.03s-.02,0-.06,0l.02.1c.17.06.28.12.34.19l.14.24.06.07s.04.06,0,.1c-.02.02-.06.03-.1.02l-.18-.11-.28-.12c-.08-.05-.11-.02-.07.09v.03s-.03-.03-.03-.03c-.02-.04-.07-.06-.16-.05l-.98.14-.91.15-.26.07c-.33.06-.64.1-.94.14-.11.01-.22.03-.33.07-.11.01-.24.02-.39.03-.04,0-.12.01-.23.04-.11.01-.22.01-.32,0l-.1.06c-.13.29-.23.47-.3.55l-.14.15c-.15.24-.31.53-.49.86-.07.12-.15.27-.23.43-.06.15-.14.3-.26.46-.26.58-.42.95-.48,1.11-.03.08-.06.18-.09.28-.03.08-.05.19-.06.32-.03.08,0,.12.09.1.07-.04.12-.05.16-.05.07-.02.11-.02.13-.02h.03s-.03.01-.03.03l-.33.13s-.04,0-.07.03c0,0-.01,0-.03,0h.13s.26,0,.26,0h.06s-.03.03-.03.03l-.3.07c-.07.02-.11.04-.14.08-.02.02-.03.06-.01.13,0,.02,0,.04,0,.06.02,0,.03.01.03.03,0,.04.04.07.12.07h.26c.07-.03.14-.04.23-.05.11-.03.22-.05.32-.04h.06s.04,0,.06.01c.04,0,.07.02.09.04.08.09.15.12.22.08l1.02-.23.43-.12h.06s.11,0,.2-.04.18-.06.26-.07c.04-.02.11-.04.2-.08.11-.05.22-.09.33-.1.02,0,.16-.04.43-.12.13-.03.23-.07.3-.1.09-.04.17-.06.23-.08.17,0,.26-.02.26-.04l.04-.06s.03.01.03.03c0,.02,0,.03,0,.03.07-.06.1-.04.09.04.02.02.04.04.06.04.04,0,.06,0,.07-.03h.03s.06,0,.06,0v-.03s0-.06,0-.06c0-.02.01-.03.03-.03v.03s-.01.1-.01.1c0,0-.02.02-.07.06v.06s0,.04-.01.06c.02,0,.03.01.03.03.02.02.08.07.18.14.02,0,.03.01.03.03.07.18.14.27.2.27.02,0,.03,0,.03-.03.02-.02.05-.03.07-.03l.03-.03s0,.01,0,.03c.02,0,.04,0,.06,0v.03s-.01.13-.01.13c.02,0,.06-.02.1-.06.05-.04.07-.07.07-.09,0,0,0-.01,0-.03.02-.02.04-.04.04-.06.02,0,.03.01.03.03,0,.02,0,.03.03.03v.03s-.06.09-.05.16c.02.02.03.07.02.13.03.11.09.15.18.11.07-.02.12-.01.16.01.06.09.05.2-.03.32-.09.06-.13.13-.11.21.01.09.02.14.02.16l-.03.32-.03.03s-.01,0-.03,0c-.02,0-.03-.01-.03-.03-.06-.03-.1-.07-.12-.14-.02-.04-.04-.06-.06-.04-.1.12-.25.19-.47.22-.11.03-.24.06-.39.09-.13.03-.27.07-.43.12-.13.03-.27.08-.43.16h-.03s-.08-.02-.13.02c-.05.04-.08.06-.1.06l-.03.03h-.13c-.03.05-.07.09-.14.11-.07.02-.11.02-.13.02l-.19.02c-.13.03-.23.11-.31.23h-.03c-.06,0-.15,0-.26.04-.11.03-.2.06-.26.07l-.27.11s-.06.02-.1.06c-.06,0-.1,0-.1,0h-.06c-.06-.01-.14,0-.23.04-.09.06-.17.09-.23.11l-.14.08-.23.08h-.1ZM75.62,44.36l.07-.06h-.06c-.06-.01-.11,0-.13.05l-.03.03h.06s.1-.02.1-.02ZM73.98,41.78l.04-.12s0-.03-.03-.03v.03s-.04.06-.05.12h.03ZM75.92,44.26c.11,0,.18,0,.23-.01h.03s-.03-.03-.03-.03l-.23.04h-.03s0,0,0,.03c.02,0,.03,0,.03-.03ZM74.18,41.31s.07-.09.08-.15v-.03s-.03,0-.03,0l-.07.12v.06s.03,0,.03,0ZM78.32,45.04s.05-.06.07-.06c.02,0,.04,0,.07-.03l.36-.13c.06,0,.14,0,.23-.04l.04-.06-.07.03c-.22.02-.38.06-.49.12-.05.04-.11.08-.2.11-.02,0-.03.02-.04.06h.03ZM78.38,44.44c.13-.05.27-.09.4-.13.13-.03.24-.06.33-.1l.07-.03s-.06,0-.06,0l-.43.09s-.1.04-.17.08c-.04.02-.1.04-.17.08h-.03s.03,0,.03,0h.03ZM79.5,44.02c.15-.03.27-.07.36-.13h.13s-.16-.03-.16-.03c-.13.07-.25.12-.33.13,0,0,0,.01,0,.03,0,0-.01,0-.03,0h.03ZM86.39,32.48v-.06c.01-.06.03-.11.05-.12h.03s-.05.22-.05.22h-.03s0-.03,0-.03ZM97.21,43.09s-.07-.02-.09-.04c0-.04,0-.08.01-.13l-.08-.23s0-.03-.03-.03c.03-.04.02-.07-.02-.1-.02-.02-.03-.03-.03-.03l-.33-.25v-.03c-.03-.11-.09-.16-.18-.14,0-.06,0-.11-.02-.13h.06s0,.05,0,.07c.02,0,.04,0,.07-.03,0-.02.02-.03.07-.03l.03-.03s0-.03-.03-.03c-.06-.05-.08-.09-.05-.13.03-.06.04-.15.05-.25v-.03s.06-.05.04-.09c0-.06,0-.11.01-.13.02-.02.04-.06.04-.12v-.06s-.06.06-.06.06c0,.08-.02.15-.05.19l-.03.03v-.03s.04-.38.04-.38c0-.04,0-.1.01-.16.03-.08.02-.16-.01-.23-.04-.05-.04-.07,0-.06.1-.12.14-.23.13-.34l.04-.06s.07-.08.08-.19c0-.06.02-.13.05-.19.05-.06.07-.1.07-.12v-.06s-.06.03-.06.03v.06s-.04,0-.04,0v-.03s.01-.13.01-.13c.01-.13.03-.22.06-.28,0-.04.03-.1.08-.19v-.06s-.06.06-.06.06c-.05.04-.17.2-.36.48-.05.08-.1.14-.14.18v.03c0,.06-.05.17-.13.31-.07.12-.12.23-.12.31,0,0,0,.01,0,.03,0,0-.01,0-.03,0v-.06s.14-.44.14-.44c.03-.04.03-.07,0-.1,0-.04.02-.08.04-.12.03-.06.05-.13.08-.22.05-.1.08-.19.09-.25,0-.02,0-.05,0-.1.03-.06,0-.11-.05-.13l.04-.09v-.03s-.06.03-.06.03l-.03.03v-.06s.24-.46.24-.46l.24-.56v-.06s0,0-.03,0c0,0,0,.01,0,.03-.02,0-.03,0-.03.03l-.07.06v-.06s.04-.04.04-.06c0-.04.02-.07.04-.09v-.06s-.03.03-.03.03l-.34.58-.04.06-.03.03v-.06s.02-.06.04-.06c.05-.1.09-.22.13-.34.05-.12.12-.25.19-.37l.42-.77.47-.92.23-.43.24-.53.27-.55c.07-.12.17-.31.27-.55.18-.33.28-.53.31-.62.11-.23.17-.37.2-.43.06-.19.21-.53.44-1.02.05-.08.1-.21.16-.37.13-.25.23-.47.32-.68.05-.1.09-.22.13-.34.05-.12.12-.25.19-.37.1-.16.21-.41.32-.74l.28-.65c.03-.08.07-.18.12-.28.05-.1.1-.23.13-.37.02-.02.03-.05,0-.1-.01-.07-.02-.12-.02-.16-.02,0-.03-.01-.03-.03,0-.02,0-.03,0-.03.07-.04.1-.09.11-.15,0-.08.01-.14.01-.16,0-.06.04-.1.11-.12,0,0,.06-.05.17-.15.19-.24.36-.4.49-.47.27-.11.47-.17.6-.21l.36-.07.66.19s.06.04.12.04c.15.01.24.06.28.15l.06.07s.05.05.09.07c.04.02.08.07.12.14,0,.02,0,.04.03.07.04,0,.07.03.09.07.08.09.11.18.11.27.02.22.03.37.03.45l-.17.5c-.16.37-.29.65-.39.83l-.16.37-.35.74c-.1.14-.19.34-.28.59-.15.29-.26.5-.31.65l-.15.24c0,.06-.02.12-.05.16l-.23.43-.24.53-.47.99-.22.33-.2.43c-.08.14-.16.3-.26.46-.1.16-.21.36-.34.58l-.48.76-.72,1.22-.63,1-.31.58c-.05.1-.1.21-.16.31-.03.08-.06.16-.08.22l-.34.61-.46.89-.24.56c-.03.08-.01.13.05.13l.03.07s-.03.06-.07.12c-.03.04,0,.09.05.13-.1.21-.15.36-.14.47,0,.02-.03.05-.07.09v.1s.09,0,.09,0l.03.07c0,.11-.03.19-.05.25-.05.04-.09.05-.13.02ZM92.89,45.89h.06s-.06-.06-.06-.06l-.1.09.03.03.07-.06ZM93.23,46.02s0-.03-.03-.03v-.06s0-.03,0-.03h-.06s-.02.07-.04.09c.04.05.06.07.06.07l.07-.03ZM94.31,46.95s-.04,0-.06,0c0-.02,0-.03,0-.03l-.1.02.03.07.13-.05ZM94.11,46.61s.02-.03.07-.03l-.06-.04c-.06,0-.11,0-.13.02-.02,0-.03.02-.04.06l.06.07.1-.09ZM93.4,45.94s.06-.02.1-.06l-.03-.03s-.07.06-.07.06v.03ZM93.23,45.63v-.16s0-.06-.01-.07l-.04.06s0,.05,0,.1c0,.02-.03.04-.07.06l.03.03s.05.04.09.04v-.06ZM93.83,46.2v-.03s-.12-.07-.12-.07h-.06s.03.03.03.03c.04.05.08.07.12.07h.03ZM93.93,45.73v-.03s0-.03-.03-.03c-.04.02-.08.01-.1,0-.04-.03-.08-.03-.13-.01-.02.02-.04.04-.04.06,0,0,.03.03.09.1h.03s.03,0,.03,0l.14-.08ZM93.46,45.27s.02-.07.04-.09l-.03-.07h-.03s-.04.06-.04.06l.02.13.03.03v-.06ZM94.14,47.35s-.05,0-.1,0c-.02,0-.02-.02,0-.06.02-.02.02-.03,0-.03,0-.02,0-.03-.03-.03-.02-.02-.05-.04-.09-.04-.02,0-.04-.01-.06-.04-.02-.02-.02-.04,0-.06v-.13c.06-.06.04-.09-.04-.1-.13-.01-.17-.07-.11-.17l-.02-.1h-.03s-.04.06-.04.06c.02.04,0,.08-.04.09-.02.02-.04.04-.04.06l-.03-.03s0-.04-.03-.07c0-.02-.02-.02-.06,0v-.03c-.03-.15-.11-.21-.24-.18-.02,0-.05,0-.1,0-.02,0-.05-.02-.09-.04-.02-.02-.07-.04-.16-.05s-.12-.05-.12-.14l.04-.41v-.06s-.02-.07-.02-.07l-.04.06c.02.07-.02.09-.1.09,0,0-.01,0-.03,0,0,0,0-.01,0-.03l.14-.53.06-.28s-.01-.11-.05-.2c-.02-.04,0-.11.05-.19l.21-.14.34-.16s.04-.06.04-.12c0-.08.06-.16.15-.21.13-.03.26-.02.38.03.06.03.07.1.01.23l-.1.44.03.07.07-.03c0-.08.04-.17.09-.25.05-.06.11-.11.17-.15.02-.02.03,0,.03.07v.03s.06-.03.06-.03l.04-.06h.03s.12.05.12.05c.04,0,.08,0,.1-.02l-.06-.04s-.03-.07.04-.06c.16-.07.36-.08.61-.01.08,0,.12.06.11.17v.1s-.03.04-.01.06c.02,0,.04,0,.06,0,.04-.02.08,0,.09.04.04.02.07.04.09.04l.18.18.17.27v.03c.07.13.03.2-.11.18-.04,0-.07.02-.07.06l-.05.16s-.05.09-.01.16c.04.09.07.16.11.2v.03s-.07,0-.07,0l-.03-.03c-.06-.03-.11-.02-.13.02v.03s-.02.05-.04.09c-.02.04-.06.07-.1.09-.02.02-.05.07-.08.15,0,.06,0,.12.02.16v.03s-.03.05-.07.09c-.05.04-.05.09-.01.16v.03c-.07.02-.07.05-.01.1,0,0,0,.01,0,.03t0,0c0,.09-.04.15-.11.18,0,.02-.04.06-.11.12-.04.02-.09.04-.13.05-.04.02-.09.05-.14.08-.11.08-.24.09-.39.03l-.13.02ZM94.05,44.74s.05-.07.07-.09c.02-.04.04-.08.04-.12l-.03-.07v.06s-.01.06-.01.06l-.07.12v.03ZM95.71,44.53s-.04-.01-.06-.04c-.02-.02-.03-.06-.02-.1.02-.02.03-.02.03,0,.04,0,.1.03.19.08l-.13.05ZM95.97,41.89s-.06-.09-.05-.13c-.02,0-.03-.02-.03-.07h.06s.12.11.12.11c.02.02.06.04.12.04,0,0,.01,0,.03,0,0,.02-.01.03-.03.03l-.17.05-.06-.04ZM97.12,39.32l.11-.21v-.03s-.03,0-.03,0l-.12.21s-.03,0-.03.03c.02,0,.03,0,.03,0h.03ZM96.69,38.71s.06,0,.07-.03c.02-.04.04-.07.04-.09v-.03s-.07.06-.07.06l-.04.06s-.03,0-.03.03h.03ZM96.94,38.44s-.06-.07-.06-.07c0,.02-.03.05-.07.09v.03s.13-.05.13-.05ZM98.69,37.18l-.03-.07-.07.09v.06s.1-.09.1-.09ZM99.96,34.78s.03,0,.04-.03c0-.04.03-.06.07-.06.02,0,.03-.02.04-.06l-.03-.03s-.04,0-.07.03c-.02.02-.02,0,0-.06h-.03c0,.08-.02.15-.05.19l.03.03Z\"><\/path><path class=\"cls-1\" d=\"M39.41,112.63l-.04-.17s.06.06.04.17Z\"><\/path><path class=\"cls-1\" d=\"M34.79,72.81s0-.03.01-.04t-.01.04Z\"><\/path><path class=\"cls-1\" d=\"M37.4,106.44s0,.03-.01.04v-.04s.01,0,.01,0Z\"><\/path><path class=\"cls-1\" d=\"M37.12,114.24c.03-.25.05-.48.07-.7,0-.21.03-.41.02-.6.01-.37,0-.7,0-1.03,0-.66,0-1.32.1-2.38,0-1.01.07-2.1.08-3.09.23-.48-.05-1.31.1-1.89l-.16-.21c.06-.2.08-.44,0-.62h-.04c.08-.28,0-.6.02-.75h-.04s-.02-.34-.02-.34l-.06.07c.05-.52,0-1.04-.11-1.49h.17c-.31-.94-.01-1.35-.37-2.19h-.04c.26-1.17-.59-1.69-.38-2.92-.03.15-.1-.04-.13-.03-.05-.53-.14-1.11.19-1.18-.07-.39-.16-.29-.29-.32.14-.03.14-.37.08-.68l-.03.15-.12-.87.3.12c-.18-.45-.34-.05-.38-.5l.21-.04c-.18-.63-.58-.94-.87-1.51-.64-2.54-.64-5.41-1.45-7.76l-.19-.08c-.26,0,.25-.73,0-.79l.07-.3c-.06-.07-.13-.24-.16-.08-.05-.27,0-.27.04-.48l-.19-.25c-.28-1.02-.1-1.94-.3-3.02-.12-.32-.19-.71-.25-1.16-.05-.44-.09-.93-.1-1.4-.02-.97.06-1.97.12-2.69.16-1.01.01-2.11-.07-3.22-.09-1.11-.13-2.26.23-3.28-.03-.07.07-.24.1-.23l.14-.96.16-.94s.03-.14.08-.38.12-.56.24-.93c.21-.73.55-1.64.89-2.29.35-.65.71-1.05.91-.84.12.11.19.36.22.81,0,.22.03.49.03.82,0,.32,0,.7,0,1.14l.06-.03c-.04.24-.08.47-.11.68-.04.21-.08.39-.12.56-.08.35-.22.66-.42.96.3.17-.12.8-.05,1.06h.03c-.35.54,0,1.24-.27,1.79.03-.01.11-.03.14-.16-.08.42-.22.99-.02,1.04-.03.25-.05.53-.08.82-.01.28-.04.58-.07.86-.04.56-.11,1.08-.26,1.41l.06-.04c-.21.37-.04.48-.14.9.03.03.04.06.04.04-.2.41,0,1.19-.07,1.52h.13s0,.83,0,.83l-.05-.31c-.17.06-.11.21-.03.42.09.21.19.48.11.79.09.55-.64,1.19-.4,1.75-.14.3.24-.27.16.15.19,0,.1-.2.26-.12-.04.41.26.63.19,1.15h.14c-.18.68.35,1.19.17,1.66-.02.68.49.37.31,1.11l.23.24c.07.29-.2.26-.05.56.11-.04.16.39.24.18.32.7,0,1.55.49,2.45-.2.26.03.72-.11.92.1,0,.21.98.32.39,0-.06,0-.14-.04-.13l.13-.09c.36.5.05,1.04.21,1.57-.07-.15-.12-.38-.17-.21l.12.5.1-.13.22.74-.16-.08c.15.36.42.43.31.9-.07.21-.26-.31-.23.09.2.48.51,1.19.67,1.82-.17-.03-.13.14-.13.32h.14c-.05.72.36.18.34.88l.09-.09-.26.24c-.15.66.36.28.11,1.03-.03-.27-.33-.07-.21.26l.11-.11c0,.18-.04.25,0,.38.06-.13.19-.1.22.18l.14-.21-.15.55c.22.36.15,1.02.37,1.15,0,0,.24.83.07,1.07.1-.2.23.26.36.11-.11.24-.12.92.08,1.15v-.06c.32.94.04,1.69.35,2.54-.17-.03-.03.44-.24.34-.09.93.61,1.61-.01,2,0,.42.19.48.25.69l.03-.1c0,.39,0,.65,0,.87,0,.22.03.42.05.72-.06.3-.34.36-.25.86.11-.17.1.04.1.24.01-.13.06-.17.14.08-.04.04-.06.1-.07.14h.03c-.03.32-.07.27-.1.11-.01,0-.04,0-.07-.06.17.33,0,.93.22.97-.05.97-.27,1.66-.4,2.47.1.1.2-.09.26-.33l-.07.58c.16,0,.11-.33.14-.51.1.35.03.7-.06,1.07-.1.37-.18.73-.12,1.15l-.14.16v.06s-.16.16-.18.28c.12.12.32.02.25.42.04.17,0,.38-.08.62-.07.23-.18.47-.25.66.01-.23-.07-.17-.13-.08-.04.2.07.34,0,.48l.17.05c-.16-.11-.28.48-.37.54.12.14.17-.28.28-.31-.17.79-.08.4-.26,1.17-.23.38-.14-.11-.34.06-.11.35-.34.68-.34,1.11l-.12-.17c-.14.33-.25.58-.32.82-.06.24-.08.47-.08.72-.35.57-.68.99-.95,1.29-.27.3-.5.5-.67.61-.34.23-.5.13-.56-.09-.06-.22-.03-.56.02-.86.03-.14.04-.28.07-.37.01-.1.03-.15.03-.15.18-.96.4-1.64.7-2.37.28-.72.62-1.5.88-2.64l.11.04Z\"><\/path><path class=\"cls-1\" d=\"M40.78,116.38v.1s-.03-.06,0-.1Z\"><\/path><path class=\"cls-1\" d=\"M42.77,117.28c-.59.67-.54,1.04-1.3,1.59-.29.31-.69.58-1.02.85-.31-.02-.41.38-.72.4l.03.15c-.11,0-.21.05-.22.16l.03.03c-.16,0-.22.16-.29.16l.03.03-.13.08.06.03c-.22.07-.39.22-.5.39l-.1-.12c-.18.42-.52.29-.64.69l.03.03c-.08,0-.14,0-.2.03h-.01l-.03.03s-.04.03-.06.04c-.03.03-.07.06-.1.09-.13.11-.21.26-.31.41-.1.14-.21.3-.34.43-.13.13-.28.23-.45.26.08,0-.01.13,0,.17-.29.21-.6.49-.59.02-.18.18-.15.28-.19.49.01-.21-.14-.14-.28-.02.01,0,.04.01.06.03l-.39.31c.06-.18.12-.35.18-.53-.22.31-.18.62-.35.69l.11-.41s-.06.07-.08.11c-.13-.14-.35.12-.56-.06-.14-.42-.27-.91-.38-1.4-.12-.49-.2-.97-.29-1.43-.03-.11-.04-.22-.07-.34,0-.07-.01-.08-.03-.13v-.1c-.04-.14-.07-.26-.12-.39-.07-.25-.19-.5-.36-.71h-.17c-.24.06.26-.37.04-.33l.07-.14c-.06-.01-.11-.07-.16,0-.04-.1,0-.11.04-.21l-.18-.07c-.23-.38-.06-.81-.23-1.22-.45-.43-.46-1.48-.48-2.1.12-.9-1.08-1.54-.92-2.46-.04-.01,0-.11.04-.11l-.24-.73s-1.15-3.56,1.58-1.41l.04-.03c.24.36.34.61.18.97.32-.05.13.32.26.39h.03c-.17.3.36.43.2.74.03-.01.11-.04.1-.1,0,.18,0,.45.2.41.07.43.33.98.12,1.33l.04-.03c-.15.21.03.21-.03.41h.06c-.14.23.12.49.08.64l.13-.03.07.34-.06-.11c-.32.14.28.19.13.49.11.21-.56.65-.32.85-.13.15.22-.17.16.03.17-.04.08-.11.24-.1-.04.18.26.21.2.45l.14-.03c-.17.34.33.44.15.69-.03.29.45.06.27.42l.21.05c.07.11-.2.16-.07.25.11-.04.14.14.23.03.27.25-.08.69.35.99-.2.16,0,.31-.15.42.13.05.07.17.25.04.01,0,0-.01-.03,0l.13-.04c.13-.03.1-.02.04.03-.06.04-.13.13-.1.14-.04.01-.04-.01-.11.06l.03.04s.06-.07.1-.1c.03,0,.04,0,.07,0-.04.04-.07.08-.11.13.03,0,.1-.08.13-.13t-.03.08c-.04.07-.07.13-.1.17-.03.04-.06.07-.06.13.04-.03.1-.06.14-.11.04-.04.08-.1.1-.11-.1.27-.08.27-.1.35l.07-.24c-.03.1-.03.13,0,.08.04-.13.15-.55.11-.37l.04-.17c-.04.17-.07.34-.11.51-.03.21,0,.08.03-.01.03-.11.03-.17.03.1-.01-.01-.07.49-.01.35v-.2s.03.1.04.04c0-.1,0-.28.03-.27,0-.07,0-.15,0-.22,0,.11,0,.21.03.31.01-.11.04-.13.06-.14.01,0,.04-.03.01-.14,0,0,0-.04.03-.06.01,0,.04,0,.1.08-.04-.06-.06-.1-.07-.15-.01-.04-.04-.1-.09-.15.04.07.09.11.11.12.01,0,.03,0,.03,0,.01-.03.04-.07.03-.13h-.03c.18-.39.65-.32.78-.71.1.12.18-.07.28.11.41-.12.21-.77.74-.4.14-.09.04-.25.08-.34h-.06c.27-.19.34-.24.5-.41.13-.03.35.16.45-.03-.13-.04-.06-.08,0-.14-.06.01-.08,0-.07-.12.04.01.07.01.1.01,0,0,0-.01-.01-.03.13-.06.13-.02.1.04.01,0,.03.03.04.07,0-.21.28-.26.15-.41.32-.24.67-.29.97-.46-.04-.1-.17-.11-.27-.08l.2-.13c-.1-.11-.15.03-.22.06.04-.36.59-.22.67-.61l.13.04v-.03s.16.06.21.04c-.06-.13-.21-.22-.09-.32,0-.18.31-.2.48-.27-.06.08.01.11.09.11.06-.06,0-.18.08-.18l-.11-.14c.09.14.28,0,.35,0-.06-.13-.17,0-.25-.05.25-.21.13-.1.36-.31.21-.02.1.14.26.19.14-.09.32-.09.38-.3l.07.15c.3-.12.41-.24.43-.5,2.43-.56,1.54.95,1.54.95-.37.83-1.01.8-1.82,1.41l-.07.04Z\"><\/path><\/g><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5e3b66c e-con-full e-flex e-con e-parent\" data-id=\"5e3b66c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5050d2c e-flex e-con-boxed e-con e-child\" data-id=\"5050d2c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-926d86c elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"926d86c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wat medische verenigingen aanbevelen v\u00f3\u00f3r een knieprothese<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b7d8ea1 elementor-widget elementor-widget-text-editor\" data-id=\"b7d8ea1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Voordat een operatie wordt overwogen, zijn er tal van behandelingsopties die gebaseerd zijn op een combinatie van medicamenteuze en niet-medicamenteuze behandelingen.3 De aanbevelingen van de wetenschappelijke verenigingen zijn gebaseerd op een alomvattende en multidisciplinaire aanpak, die is opgebouwd rond verschillende complementaire pijlers:5<\/p><p> <\/p><ul><li style=\"list-style-type: none;\"><ul><li aria-level=\"1\"><span style=\"font-weight: 400;\">Het begint met<\/span> <b>een beter begrip van de aandoening<\/b><span style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">: therapeutische educatie helpt om meer te weten te komen over artrose, de mogelijke opties in kaart te brengen en te leren hoe je je gewrichten kunt ontzien terwijl je in het dagelijks leven actief blijft.<\/span><\/span><\/li><\/ul><\/li><\/ul><p> <\/p><ul><li style=\"list-style-type: none;\"><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Aangepaste lichaamsbeweging <\/b><span style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">vormt hierin een centrale pijler. Meestal gaat het om oefeningen met een lage belasting, zoals wandelen, fietsen, zwemmen of krachttraining, vooral wanneer de knie of heup betrokken is. Ook andere activiteiten, zoals yoga of tai chi, kunnen een rol spelen.<\/span><\/span><\/li><\/ul><\/li><\/ul><p> <\/p><ul><li style=\"list-style-type: none;\"><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Een gezonde levensstijl<\/b> <span style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">vormt ook een integraal onderdeel van de behandeling, waarbij indien nodig aandacht wordt besteed aan het gewicht, aan aanpassingen in de dagelijkse handelingen en, indien nodig, aan het gebruik van hulpmiddelen. Functionele revalidatie speelt een sleutelrol, met name door middel van fysiotherapie, om de beweeglijkheid en stabiliteit van het gewricht te verbeteren.<\/span><\/span><\/li><\/ul><\/li><\/ul><p> <\/p><ul><li style=\"list-style-type: none;\"><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Farmacologische behandelingen<\/b>, zoals ontstekingsremmers, cortico\u00efdinjecties of intra-articulair hyaluronzuur, wanneer de andere maatregelen onvoldoende zijn.<\/li><\/ul><\/li><\/ul><p> <\/p><ul><li style=\"list-style-type: none;\"><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Bij complexere vormen kan de behandeling zelfs zo ver gaan dat een<\/span> <b>operatie<\/b> <span style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">wordt overwogen, waarbij een totale knieprothese wordt geplaatst bij pati\u00ebnten die daarvoor in aanmerking komen en bij wie de pijn niet of niet meer reageert op medische of fysiotherapeutische behandelingen.<\/span><\/span><\/li><\/ul><\/li><li style=\"list-style-type: none;\"> <\/li><\/ul><p>V\u00f3\u00f3r elke therapeutische beslissing zullen de artsen de impact van uw artrose op het dagelijks leven, uw pijn en uw levenskwaliteit beoordelen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c9d1928 e-con-full e-flex e-con e-child\" data-id=\"c9d1928\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-92fc3a8 e-con-full e-flex e-con e-child\" data-id=\"92fc3a8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-d8a1862 e-con-full e-flex e-con e-child\" data-id=\"d8a1862\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-35caffe elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"35caffe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Een blik vanuit een ander perspectief \u2013 Prof. Camille Choufani<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7dfae5b elementor-widget elementor-widget-image\" data-id=\"7dfae5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"110\" height=\"110\" src=\"https:\/\/arthroseactive.be\/wp-content\/uploads\/2026\/03\/kiomed-medecin-_0001_owskkq22f9kmtqx5zbri.png\" class=\"attachment-thumbnail size-thumbnail wp-image-4018\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca0c56f elementor-widget elementor-widget-text-editor\" data-id=\"ca0c56f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><em>\u275dVoor ik opereer, heb ik het altijd over de 20 tot 30 % van de pati\u00ebnten die pijn blijven houden na een technisch geslaagde prothese. Alles moet worden ingezet voor de ingreep, om geen spijt te krijgen van een chirurgische keuze. Te meer omdat deze maatregelen, mocht een operatie alsnog nodig blijken, toelaten om de pati\u00ebnt optimaal voor te bereiden (onder meer revalidatie en gewichtsverlies).\u275e  <\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7eced66 e-flex e-con-boxed e-con e-child\" data-id=\"7eced66\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b6573e1 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"b6573e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wanneer de \u2018klassieke\u2019 behandelingen niet meer werken<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f855a4a elementor-widget elementor-widget-text-editor\" data-id=\"f855a4a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Meestal zorgen aangepaste lichaamsbeweging, revalidatie en medicamenteuze behandelingen bij veel pati\u00ebnten voor een verbetering van de symptomen. <\/span><b>Maar niet bij iedereen.<\/b><\/p><p> <\/p><p>Bij sommige mensen verandert er, ondanks een goed uitgevoerde behandeling, eigenlijk niets<b>.<\/b> <span style=\"font-weight: 400;\"><strong>De pijn, de stijfheid en het verlies van gewrichtsfunctie blijven aanwezig<\/strong>, ook al is de behandeling goed uitgevoerd.<sup>6<\/sup><\/span><\/p><p> <\/p><p> <span style=\"font-weight: 400;\">In deze context spreekt<\/span> <b>men van moeilijk te behandelen artrose, ofwel \u201erefractaire<sup>6<\/sup>\u201c.<\/b><\/p><p>Hardnekkige artrose is een specifieke vorm van de aandoening waarbij <span style=\"font-weight: 400;\">de verwachte resultaten uitblijven en die een andere therapeutische aanpak vereist.<\/span><\/p><p> <\/p><p> <span style=\"font-weight: 400;\">Hardnekkige artrose komt ook<\/span> voor bij jonge of sportieve pati\u00ebnten, <span style=\"font-weight: 400;\">met name na een trauma. Deze aandoening houdt meestal verband met een combinatie van factoren<\/span> die ten grondslag liggen aan artrose.<sup>8<\/sup><\/p><p> <\/p><p>In dergelijke situaties verdwijnt de pijn niet, <span style=\"font-weight: 400;\">stoten de gebruikelijke behandelingsmethoden op hun grenzen en rijst onvermijdelijk de vraag naar andere strategie\u00ebn.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2cbaf4b elementor-widget elementor-widget-button\" data-id=\"2cbaf4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/arthroseactive.be\/nl\/ik-heb-alles-geprobeerd-maar-ik-heb-nog-steeds-pijn-inzicht-in-moeilijk-te-behandelen-artrose\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Lees ons artikel hierover<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-88345e4 e-flex e-con-boxed e-con e-child\" data-id=\"88345e4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ebc90b1 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"ebc90b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Welke behandelingsmogelijkheden zijn er voordat een knieprothese wordt overwogen?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20fb3e4 elementor-widget elementor-widget-text-editor\" data-id=\"20fb3e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Het gaat er in de eerste plaats om de behandeling af te stemmen op het specifieke profiel van de pati\u00ebnt, in plaats van een standaardaanpak te volgen<sup>\u2075,\u2079<\/sup>: aanpassing van de behandelingen, een op maat gemaakte aanpak van pijn (nociceptieve, centrale of neuropathische pijn), een programma voor gewichtsverlies of andere gerichte benaderingen.<\/span><\/p><p> <\/p><p><b>Een gedeeltelijke of totale knieprothese behoort tot de mogelijkheden, maar alleen in welbepaalde gevallen.<\/b><\/p><p> <\/p><p><span style=\"font-weight: 400;\"> Deze behandeling is ge\u00efndiceerd bij radiologisch vastgestelde gevorderde artrose, gepaard gaande met aanhoudende en invaliderende pijn, ernstige functionele beperkingen en een aantoonbaar falen van conservatieve behandelingen, in het kader van een gezamenlijke beslissing op basis van gevalideerde criteria en de daadwerkelijke impact van de aandoening op het dagelijks leven.<sup>3,10<\/sup><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c6573da elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"c6573da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"68\" height=\"66\" src=\"https:\/\/arthroseactive.be\/wp-content\/uploads\/2026\/03\/icon-loupe.png\" class=\"attachment-thumbnail size-thumbnail wp-image-4152\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\"><b>Wist u dat?<\/b><br>De verwachtingen ten aanzien van een operatie zijn vaak erg hooggespannen, met name wat betreft pijn, terwijl de voordelen soms worden overschat<sup>\u00b3<\/sup>: tussen de 5 en 40 % van de pati\u00ebnten meldt weinig of geen verbetering na een totale knieprothese.<sup>\u2074<\/sup><\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-286c792 elementor-widget elementor-widget-text-editor\" data-id=\"286c792\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Ten slotte is een operatie niet altijd mogelijk.<\/strong><\/p><p>Leeftijd, activiteitsniveau, geschiktheid voor een operatie of het operatierisico in verband met bepaalde aandoeningen kunnen ertoe leiden dat de voorkeur wordt gegeven aan een conservatieve behandeling, soms voor langere tijd.<sup>11<\/sup><\/p><p> <\/p><p>Naast de klassieke behandelingsopties en chirurgie zijn er tegenwoordig nieuwe therapeutische benaderingen beschikbaar of in ontwikkeling voor de zogenaamde refractaire vormen.<sup>12<\/sup><\/p><p> <\/p><p>Bepaalde recente benaderingen, zoals injecteerbare biomaterialen op basis van <span style=\"text-decoration: underline;\"><a href=\"https:\/\/arthroseactive.be\/nl\/parijse-champignons-en-gezonde-gewrichten-wat-zegt-het-onderzoek\/\"><strong>CM-Chitosan<\/strong><\/a><\/span>, \u00e9largissent les verbreden de mogelijkheden voor de aanpak van knieartrose.<sup>12<\/sup><\/p><p> <\/p><p>Ook andere innovatieve strategie\u00ebn komen op, zoals <strong>trans-arteri\u00eble micro-embolisatie (TAME) of thermocoagulatie via radiofrequentie<\/strong> van de geniculaire zenuwen, die wordt bestudeerd bij pati\u00ebnten met chronische gewrichtspijn die niet reageren op conservatieve behandelingen of die blijven aanhouden na chirurgie.<sup>11<\/sup><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-186cf2f elementor-widget elementor-widget-button\" data-id=\"186cf2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/arthroseactive.be\/nl\/parijse-champignons-en-gezonde-gewrichten-wat-zegt-het-onderzoek\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Alle nieuwe benaderingen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5ecc1a0 e-con-full e-flex e-con e-child\" data-id=\"5ecc1a0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a62e983 e-con-full e-flex e-con e-child\" data-id=\"a62e983\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<a class=\"elementor-element elementor-element-deefe2e e-con-full e-flex e-con e-child\" data-id=\"deefe2e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/arthroseactive.be\/nl\/quiz-hardnekkige-artrose\/\" target=\"_blank\">\n\t\t<div class=\"elementor-element elementor-element-3c281e0 e-con-full e-flex e-con e-child\" data-id=\"3c281e0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-95e0226 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"95e0226\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"65\" height=\"65\" src=\"https:\/\/arthroseactive.be\/wp-content\/uploads\/2026\/03\/Group-395322307-2.png\" class=\"attachment-medium_large size-medium_large wp-image-4154\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8796d5c e-con-full e-flex e-con e-child\" data-id=\"8796d5c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e160e41 elementor-widget elementor-widget-heading\" data-id=\"e160e41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Quiz: Heb ik refractaire artrose? <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cfdff18 e-con-full e-flex e-con e-child\" data-id=\"cfdff18\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-884d698 e-transform elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"884d698\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_rotateZ_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-15,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_hover_laptop&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"38\" viewBox=\"0 0 40 38\" fill=\"none\"><rect width=\"40\" height=\"38\" rx=\"10\" fill=\"#2D2C78\"><\/rect><path d=\"M12 18.9786C12 19.45 12.3952 19.8357 12.8782 19.8357H25.0196L21.2432 23.5214C20.8919 23.8643 20.8919 24.4 21.2432 24.7429C21.4189 24.9143 21.6384 25 21.858 25C22.0775 25 22.2971 24.9143 22.4727 24.7429L27.742 19.6C27.7859 19.5571 27.8298 19.5143 27.8518 19.4714C27.8518 19.4714 27.8738 19.4286 27.8957 19.4071C27.8957 19.3857 27.9177 19.3429 27.9396 19.3214C27.9396 19.3 27.9396 19.2571 27.9616 19.2357C27.9616 19.2143 27.9616 19.1929 27.9835 19.1714C28.0055 19.0643 28.0055 18.9571 27.9835 18.8286C27.9835 18.8071 27.9835 18.7857 27.9616 18.7643C27.9616 18.7429 27.9616 18.7 27.9396 18.6786C27.9396 18.6571 27.9177 18.6143 27.8957 18.5929C27.8957 18.5714 27.8957 18.55 27.8518 18.5286C27.8298 18.4857 27.7859 18.4429 27.742 18.4L22.4727 13.2571C22.1214 12.9143 21.5726 12.9143 21.2213 13.2571C20.87 13.6 20.87 14.1357 21.2213 14.4786L24.9976 18.1643H12.8782C12.3952 18.1643 12 18.55 12 19.0214V18.9786Z\" fill=\"white\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<a class=\"elementor-element elementor-element-20ecf70 e-con-full e-flex e-con e-child\" data-id=\"20ecf70\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/arthroseactive.be\/nl\/quiz-mijn-actieve-artrose-traject-beter-bepalen\/\" target=\"_blank\">\n\t\t<div class=\"elementor-element elementor-element-f0685a5 e-con-full e-flex e-con e-child\" data-id=\"f0685a5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2185709 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"2185709\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"58\" height=\"63\" src=\"https:\/\/arthroseactive.be\/wp-content\/uploads\/2026\/03\/Group.png\" class=\"attachment-medium_large size-medium_large wp-image-4155\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-141525b e-con-full e-flex e-con e-child\" data-id=\"141525b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-53405eb elementor-widget elementor-widget-heading\" data-id=\"53405eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><b>Quiz:<\/b> Hoe ver ben ik in mijn artrose-traject&nbsp;? <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-37e3821 e-con-full e-flex e-con e-child\" data-id=\"37e3821\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-27b0d87 e-transform elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"27b0d87\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_rotateZ_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-15,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_hover_laptop&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"38\" viewBox=\"0 0 40 38\" fill=\"none\"><rect width=\"40\" height=\"38\" rx=\"10\" fill=\"#2D2C78\"><\/rect><path d=\"M12 18.9786C12 19.45 12.3952 19.8357 12.8782 19.8357H25.0196L21.2432 23.5214C20.8919 23.8643 20.8919 24.4 21.2432 24.7429C21.4189 24.9143 21.6384 25 21.858 25C22.0775 25 22.2971 24.9143 22.4727 24.7429L27.742 19.6C27.7859 19.5571 27.8298 19.5143 27.8518 19.4714C27.8518 19.4714 27.8738 19.4286 27.8957 19.4071C27.8957 19.3857 27.9177 19.3429 27.9396 19.3214C27.9396 19.3 27.9396 19.2571 27.9616 19.2357C27.9616 19.2143 27.9616 19.1929 27.9835 19.1714C28.0055 19.0643 28.0055 18.9571 27.9835 18.8286C27.9835 18.8071 27.9835 18.7857 27.9616 18.7643C27.9616 18.7429 27.9616 18.7 27.9396 18.6786C27.9396 18.6571 27.9177 18.6143 27.8957 18.5929C27.8957 18.5714 27.8957 18.55 27.8518 18.5286C27.8298 18.4857 27.7859 18.4429 27.742 18.4L22.4727 13.2571C22.1214 12.9143 21.5726 12.9143 21.2213 13.2571C20.87 13.6 20.87 14.1357 21.2213 14.4786L24.9976 18.1643H12.8782C12.3952 18.1643 12 18.55 12 19.0214V18.9786Z\" fill=\"white\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-211ba56 e-con-full e-flex e-con e-child\" data-id=\"211ba56\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bc31ad7 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"bc31ad7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Deel dit artikel<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-886dc96 elementor-widget elementor-widget-elementskit-social-share\" data-id=\"886dc96\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-social-share.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\t\t<ul class=\"ekit_socialshare\">\n                            <li class=\"elementor-repeater-item-1899917\" data-social=\"facebook\">\n                    <div class=\"facebook\">\n                        \n                        <i aria-hidden=\"true\" class=\"icon icon-facebook\"><\/i>                        \n                                                                                            <\/div>\n                <\/li>\n                                            <li class=\"elementor-repeater-item-16f8fda\" data-social=\"twitter\">\n                    <div class=\"twitter\">\n                        \n                        <i aria-hidden=\"true\" class=\"icon icon-twitter\"><\/i>                        \n                                                                                            <\/div>\n                <\/li>\n                                            <li class=\"elementor-repeater-item-d2b33ab\" data-social=\"linkedin\">\n                    <div class=\"linkedin\">\n                        \n                        <i aria-hidden=\"true\" class=\"icon icon-linkedin\"><\/i>                        \n                                                                                            <\/div>\n                <\/li>\n                                    <\/ul>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-19636c9 e-con-full e-flex e-con e-child\" data-id=\"19636c9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7bc0de1 elementor-widget elementor-widget-text-editor\" data-id=\"7bc0de1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-size: 13px;\"><i><span style=\"font-weight: 400;\">De informatie op Arthrose Active is uitsluitend bedoeld ter voorlichting en vormt in geen geval een vervanging voor medisch advies. De diagnose, de keuze van de behandelingen en de aanpassing daarvan zijn uitsluitend voorbehouden aan een zorgverlener. CM-Chitosan is een medisch hulpmiddel van klasse III. Het toedienen ervan moet gebeuren door een zorgverlener die ervaring heeft met intra-articulaire injecties.   <\/span><\/i><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b73ccf6 elementor-widget elementor-widget-image\" data-id=\"b73ccf6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"508\" height=\"93\" src=\"https:\/\/arthroseactive.be\/wp-content\/uploads\/2025\/12\/Fichier-15logo-arthrose-active-3.png\" class=\"attachment-large size-large wp-image-4156\" alt=\"\" srcset=\"https:\/\/arthroseactive.be\/wp-content\/uploads\/2025\/12\/Fichier-15logo-arthrose-active-3.png 508w, https:\/\/arthroseactive.be\/wp-content\/uploads\/2025\/12\/Fichier-15logo-arthrose-active-3-300x55.png 300w\" sizes=\"(max-width: 508px) 100vw, 508px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62a626d elementor-widget elementor-widget-text-editor\" data-id=\"62a626d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ol><li>Dell\u2019Isola A, Recenti F, Giardulli B, Lawford BJ, Kiadaliri A. Osteoarthritis year in review 2025: Epidemiology and therapy. Osteoarthritis and Cartilage. 2025;33(11):1300-1306.   doi:10.1016\/j.joca.2025.08.015<\/li><li>Costello CA, Rockel JS, Liu M, et al. Individual participant data meta-analysis of metabolomics on sustained knee pain in primary osteoarthritis patients. Rheumatology (Oxford). 2022;62(5):1964-1971.    doi:10.1093\/rheumatology\/keac545<\/li><li><g id=\"gid_0\">Jacobs H, Seeber GH, Lazovic D, Maus U, Hoffmann F. Ziektebelasting en verwachtingen ten aanzien van chirurgie bij pati\u00ebnten v\u00f3\u00f3r een totale knieprothese: resultaten van de prospectieve FInGK-studie<\/g>. <g id=\"gid_2\">Knee<\/g>. <g id=\"gid_3\">2023;41:257-265. doi:10.1016\/j.knee.2023.01.020<\/g>   <\/li><li>Bonasia DE, Palazzolo A, Cottino U, et al. Be\u00efnvloedbare en niet-be\u00efnvloedbare voorspellende factoren in verband met de resultaten van totale knieprothesen. Joints. 2019;7(1):13-18. doi:10.1055\/s-0039-1678563<\/li><li>Overton C, Nelson AE, Neogi T. Osteoarthritis Treatment Guidelines from Six Professional Societies: Similarities and Differences. Rheum Dis Clin North Am. 2022;48(3):637-657.   doi:10.1016\/j.rdc.2022.03.009<\/li><li>Mandell BF, Lipani J. REFRACTORY OSTEOARTHRITIS: Differential Diagnosis and Therapy. Rheumatic Disease Clinics of North America. 1995;21(1):163-178.   doi:10.1016\/S0889-857X(21)00377-X<\/li><li>Courties A, Kouki I, Soliman N, Mathieu S, Sellam J. Osteoarthritis year in review 2024: Epidemiology and therapy. Osteoarthritis and Cartilage. 2024;32(11):1397-1404.   doi:10.1016\/j.joca.2024.07.014<\/li><li>Kloppenburg M, Berenbaum F. Osteoarthritis year in review 2019: epidemiology and therapy. Osteoarthritis Cartilage. 2020;28(3):242-248.   doi:10.1016\/j.joca.2020.01.002<\/li><li>Raman R, Henrotin Y, Chevalier X, et al. Beslissingsalgoritmen voor herbehandeling met viscosupplementatie bij pati\u00ebnten met knieartrose: aanbevelingen van de EUROpean VIScosupplementation COnsensus Group (EUROVISCO). Cartilage. 2018;9(3):263-275. doi:10.1177\/1947603517693043<\/li><li><g id=\"gid_0\">Skou ST, Roos EM, Laursen MB, et al. Criteria die worden gehanteerd bij het bepalen van de geschiktheid voor een totale knieprothese \u2013 Tussen denken en doen<\/g>. <g id=\"gid_1\"><g id=\"gid_2\">Knee<\/g><\/g>. <g id=\"gid_3\">2016;23(2):300-305. doi:10.1016\/j.knee.2015.08.012<\/g>    <\/li><li>Wilms LM, Jannusch K, Weiss D, et al. Transarterial microembolization for the management of refractory chronic joint pain in osteoarthritis. Rofo. 2024;196(12):1236-1245.    doi:10.1055\/a-2288-5743<\/li><li>P.J. Emans, W. Weyenberg, N. Portelange, M. Chausson, P. Van Overschelde, G. Skaliczki, D. Haverkamp. Single injection of carboxymethyl-chitosan for the symptomatic treatment of knee osteoarthritis: 12-month follow-up from the multicentric PIONEER clinical study. Osteoarthritis and Cartilage Open Volume 7, Issue 2, June 2025, 100605. DOI : https:\/\/doi.org\/10.1016\/j.ocarto.2025.100605<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-93bfe07 e-con-full ton-container-bleu e-flex e-con e-parent\" data-id=\"93bfe07\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d6e448b elementor-widget elementor-widget-heading\" data-id=\"d6e448b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ontvang ons nieuws<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-98f334d elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"98f334d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tOntvang elke maand duidelijke en begrijpelijke tips en advies voor het dagelijks leven met artrose.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46db74f eael-gravity-form-button-full-width elementor-widget__width-initial elementor-widget elementor-widget-eael-gravity-form\" data-id=\"46db74f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-gravity-form.default\">\n\t\t\t\t\t\t\t\t<div class=\"eael-contact-form eael-gravity-form eael-custom-radio-checkbox eael-contact-form-align-default\">\n\t\t        <script>\nvar gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),document.addEventListener(\"gform\/theme\/scripts_loaded\",function(){gform.themeScriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,themeScriptsLoaded:!1,isFormEditor:()=>\"function\"==typeof InitializeEditor,callIfLoaded:function(o){return!(!gform.domLoaded||!gform.scriptsLoaded||!gform.themeScriptsLoaded&&!gform.isFormEditor()||(gform.isFormEditor()&&console.warn(\"The use of gform.initializeOnLoaded() is deprecated in the form editor context and will be removed in Gravity Forms 3.1.\"),o(),0))},initializeOnLoaded:function(o){gform.callIfLoaded(o)||(document.addEventListener(\"gform_main_scripts_loaded\",()=>{gform.scriptsLoaded=!0,gform.callIfLoaded(o)}),document.addEventListener(\"gform\/theme\/scripts_loaded\",()=>{gform.themeScriptsLoaded=!0,gform.callIfLoaded(o)}),window.addEventListener(\"DOMContentLoaded\",()=>{gform.domLoaded=!0,gform.callIfLoaded(o)}))},hooks:{action:{},filter:{}},addAction:function(o,r,e,t){gform.addHook(\"action\",o,r,e,t)},addFilter:function(o,r,e,t){gform.addHook(\"filter\",o,r,e,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,r){gform.removeHook(\"action\",o,r)},removeFilter:function(o,r,e){gform.removeHook(\"filter\",o,r,e)},addHook:function(o,r,e,t,n){null==gform.hooks[o][r]&&(gform.hooks[o][r]=[]);var d=gform.hooks[o][r];null==n&&(n=r+\"_\"+d.length),gform.hooks[o][r].push({tag:n,callable:e,priority:t=null==t?10:t})},doHook:function(r,o,e){var t;if(e=Array.prototype.slice.call(e,1),null!=gform.hooks[r][o]&&((o=gform.hooks[r][o]).sort(function(o,r){return o.priority-r.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==r?t.apply(null,e):e[0]=t.apply(null,e)})),\"filter\"==r)return e[0]},removeHook:function(o,r,t,n){var e;null!=gform.hooks[o][r]&&(e=(e=gform.hooks[o][r]).filter(function(o,r,e){return!!(null!=n&&n!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][r]=e)}});\n<\/script>\n\n                <div class='gf_browser_gecko gform_wrapper gform-theme gform-theme--foundation gform-theme--framework gform-theme--orbital' data-form-theme='orbital' data-form-index='0' id='gform_wrapper_3' style='display:none'><style>#gform_wrapper_3[data-form-index=\"0\"].gform-theme,[data-parent-form=\"3_0\"]{--gf-color-primary: #204ce5;--gf-color-primary-rgb: 32, 76, 229;--gf-color-primary-contrast: #fff;--gf-color-primary-contrast-rgb: 255, 255, 255;--gf-color-primary-darker: #001AB3;--gf-color-primary-lighter: #527EFF;--gf-color-secondary: #fff;--gf-color-secondary-rgb: 255, 255, 255;--gf-color-secondary-contrast: #112337;--gf-color-secondary-contrast-rgb: 17, 35, 55;--gf-color-secondary-darker: #F5F5F5;--gf-color-secondary-lighter: #FFFFFF;--gf-color-out-ctrl-light: rgba(17, 35, 55, 0.1);--gf-color-out-ctrl-light-rgb: 17, 35, 55;--gf-color-out-ctrl-light-darker: rgba(104, 110, 119, 0.35);--gf-color-out-ctrl-light-lighter: #F5F5F5;--gf-color-out-ctrl-dark: #585e6a;--gf-color-out-ctrl-dark-rgb: 88, 94, 106;--gf-color-out-ctrl-dark-darker: #112337;--gf-color-out-ctrl-dark-lighter: rgba(17, 35, 55, 0.65);--gf-color-in-ctrl: #fff;--gf-color-in-ctrl-rgb: 255, 255, 255;--gf-color-in-ctrl-contrast: #112337;--gf-color-in-ctrl-contrast-rgb: 17, 35, 55;--gf-color-in-ctrl-darker: #F5F5F5;--gf-color-in-ctrl-lighter: #FFFFFF;--gf-color-in-ctrl-primary: #204ce5;--gf-color-in-ctrl-primary-rgb: 32, 76, 229;--gf-color-in-ctrl-primary-contrast: #fff;--gf-color-in-ctrl-primary-contrast-rgb: 255, 255, 255;--gf-color-in-ctrl-primary-darker: #001AB3;--gf-color-in-ctrl-primary-lighter: #527EFF;--gf-color-in-ctrl-light: rgba(17, 35, 55, 0.1);--gf-color-in-ctrl-light-rgb: 17, 35, 55;--gf-color-in-ctrl-light-darker: rgba(104, 110, 119, 0.35);--gf-color-in-ctrl-light-lighter: #F5F5F5;--gf-color-in-ctrl-dark: #585e6a;--gf-color-in-ctrl-dark-rgb: 88, 94, 106;--gf-color-in-ctrl-dark-darker: #112337;--gf-color-in-ctrl-dark-lighter: rgba(17, 35, 55, 0.65);--gf-radius: 3px;--gf-font-size-secondary: 14px;--gf-font-size-tertiary: 13px;--gf-icon-ctrl-number: url(\"data:image\/svg+xml,%3Csvg width='8' height='14' viewBox='0 0 8 14' fill='none' xmlns='http:\/\/www.w3.org\/2000\/svg'%3E%3Cpath fill-rule='evenodd' clip-rule='evenodd' d='M4 0C4.26522 5.96046e-08 4.51957 0.105357 4.70711 0.292893L7.70711 3.29289C8.09763 3.68342 8.09763 4.31658 7.70711 4.70711C7.31658 5.09763 6.68342 5.09763 6.29289 4.70711L4 2.41421L1.70711 4.70711C1.31658 5.09763 0.683417 5.09763 0.292893 4.70711C-0.0976311 4.31658 -0.097631 3.68342 0.292893 3.29289L3.29289 0.292893C3.48043 0.105357 3.73478 0 4 0ZM0.292893 9.29289C0.683417 8.90237 1.31658 8.90237 1.70711 9.29289L4 11.5858L6.29289 9.29289C6.68342 8.90237 7.31658 8.90237 7.70711 9.29289C8.09763 9.68342 8.09763 10.3166 7.70711 10.7071L4.70711 13.7071C4.31658 14.0976 3.68342 14.0976 3.29289 13.7071L0.292893 10.7071C-0.0976311 10.3166 -0.0976311 9.68342 0.292893 9.29289Z' fill='rgba(17, 35, 55, 0.65)'\/%3E%3C\/svg%3E\");--gf-icon-ctrl-select: url(\"data:image\/svg+xml,%3Csvg width='10' height='6' viewBox='0 0 10 6' fill='none' xmlns='http:\/\/www.w3.org\/2000\/svg'%3E%3Cpath fill-rule='evenodd' clip-rule='evenodd' d='M0.292893 0.292893C0.683417 -0.097631 1.31658 -0.097631 1.70711 0.292893L5 3.58579L8.29289 0.292893C8.68342 -0.0976311 9.31658 -0.0976311 9.70711 0.292893C10.0976 0.683417 10.0976 1.31658 9.70711 1.70711L5.70711 5.70711C5.31658 6.09763 4.68342 6.09763 4.29289 5.70711L0.292893 1.70711C-0.0976311 1.31658 -0.0976311 0.683418 0.292893 0.292893Z' fill='rgba(17, 35, 55, 0.65)'\/%3E%3C\/svg%3E\");--gf-icon-ctrl-search: url(\"data:image\/svg+xml,%3Csvg width='640' height='640' xmlns='http:\/\/www.w3.org\/2000\/svg'%3E%3Cpath d='M256 128c-70.692 0-128 57.308-128 128 0 70.691 57.308 128 128 128 70.691 0 128-57.309 128-128 0-70.692-57.309-128-128-128zM64 256c0-106.039 85.961-192 192-192s192 85.961 192 192c0 41.466-13.146 79.863-35.498 111.248l154.125 154.125c12.496 12.496 12.496 32.758 0 45.254s-32.758 12.496-45.254 0L367.248 412.502C335.862 434.854 297.467 448 256 448c-106.039 0-192-85.962-192-192z' fill='rgba(17, 35, 55, 0.65)'\/%3E%3C\/svg%3E\");--gf-label-space-y-secondary: var(--gf-label-space-y-md-secondary);--gf-ctrl-border-color: #686e77;--gf-ctrl-size: var(--gf-ctrl-size-md);--gf-ctrl-label-color-primary: #112337;--gf-ctrl-label-color-secondary: #112337;--gf-ctrl-choice-size: var(--gf-ctrl-choice-size-md);--gf-ctrl-checkbox-check-size: var(--gf-ctrl-checkbox-check-size-md);--gf-ctrl-radio-check-size: var(--gf-ctrl-radio-check-size-md);--gf-ctrl-btn-font-size: var(--gf-ctrl-btn-font-size-md);--gf-ctrl-btn-padding-x: var(--gf-ctrl-btn-padding-x-md);--gf-ctrl-btn-size: var(--gf-ctrl-btn-size-md);--gf-ctrl-btn-border-color-secondary: #686e77;--gf-ctrl-file-btn-bg-color-hover: #EBEBEB;--gf-field-img-choice-size: var(--gf-field-img-choice-size-md);--gf-field-img-choice-card-space: var(--gf-field-img-choice-card-space-md);--gf-field-img-choice-check-ind-size: var(--gf-field-img-choice-check-ind-size-md);--gf-field-img-choice-check-ind-icon-size: var(--gf-field-img-choice-check-ind-icon-size-md);--gf-field-pg-steps-number-color: rgba(17, 35, 55, 0.8);}<\/style>\n                        <div class='gform_heading'>\n                            <p class='gform_description'><\/p>\n                        <\/div><form method='post' enctype='multipart\/form-data'  id='gform_3'  action='\/nl\/wp-json\/wp\/v2\/posts\/4544' data-formid='3' novalidate>\n                        <div class='gform-body gform_body'><div id='gform_fields_3' class='gform_fields top_label form_sublabel_below description_below validation_below'><div id=\"field_3_6\" class=\"gfield gfield--type-honeypot gform_validation_container field_sublabel_below gfield--has-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_6'>URL<\/label><div class='ginput_container'><input name='input_6' id='input_3_6' type='text' value='' autocomplete='new-password'\/><\/div><div class='gfield_description' id='gfield_description_3_6'>Dit veld is bedoeld voor validatiedoeleinden en moet niet worden gewijzigd.<\/div><\/div><div id=\"field_3_1\" class=\"gfield gfield--type-email gfield--input-type-email gfield--width-full gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_1'>Schrijf u in voor de nieuwsbrief om elke maand onze tips voor actieve artrose te ontvangen:<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(Vereist)<\/span><\/span><\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_1' id='input_3_1' type='email' value='' class='large'   placeholder='Voer uw e-mailadres in' aria-required=\"true\" aria-invalid=\"false\"  \/>\n                        <\/div><\/div><fieldset id=\"field_3_3\" class=\"gfield gfield--type-checkbox gfield--type-choice gfield--input-type-checkbox field_sublabel_below gfield--no-description field_description_below hidden_label field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label gfield_label_before_complex' >Zonder titel<\/legend><div class='ginput_container ginput_container_checkbox'><div class='gfield_checkbox ' id='input_3_3'><div class='gchoice gchoice_3_3_1'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_3.1' type='checkbox'  value='Ik ken mijn parcours'  id='choice_3_3_1'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_3_3_1' id='label_3_3_1' class='gform-field-label gform-field-label--type-inline'>Ik ken mijn parcours<\/label>\n\t\t\t\t\t\t\t<\/div><\/div><\/div><\/fieldset><div id=\"field_3_4\" class=\"gfield gfield--type-select gfield--input-type-select gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_4'>Mijn ervaring met Artrose Active:<\/label><div class='ginput_container ginput_container_select'><select name='input_4' id='input_3_4' class='large gfield_select'     aria-invalid=\"false\" ><option value='Prestatietraject' >Prestatietraject<\/option><option value='Ontdekkingsroute' >Ontdekkingsroute<\/option><option value='Evenwichtsparcours' >Evenwichtsparcours<\/option><option value='Masteropleiding' >Masteropleiding<\/option><option value='Herintredingstraject' >Herintredingstraject<\/option><\/select><\/div><\/div><fieldset id=\"field_3_5\" class=\"gfield gfield--type-address gfield--input-type-address gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label screen-reader-text gfield_label_before_complex' ><\/legend>    \n                    <div class='ginput_complex ginput_container ginput_container_address gform-grid-row' id='input_3_5' >\n                        <input type='hidden' class='gform_hidden' name='input_5.4' id='input_3_5_4' value=''\/><input type='hidden' class='gform_hidden' name='input_5.6' id='input_3_5_6' value='' \/>\n                    <div class='gf_clear gf_clear_complex'><\/div>\n                <\/div><\/fieldset><\/div><\/div>\n        <div class='gform-footer gform_footer top_label'> <input type='image' src='https:\/\/arthroseactive.be\/wp-content\/uploads\/2025\/12\/arthrose-active-button-form-newsletter.png' id='gform_submit_button_3' onclick='gform.submission.handleButtonClick(this);' data-submission-type='submit' class='gform_button button gform_image_button' alt='Versturen'  \/> \n            <input type='hidden' class='gform_hidden' name='gform_submission_method' data-js='gform_submission_method_3' value='postback' \/>\n            <input type='hidden' class='gform_hidden' name='gform_theme' data-js='gform_theme_3' id='gform_theme_3' value='orbital' \/>\n            <input type='hidden' class='gform_hidden' name='gform_style_settings' data-js='gform_style_settings_3' id='gform_style_settings_3' value='' \/>\n            <input type='hidden' class='gform_hidden' name='is_submit_3' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='3' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_currency' data-currency='EUR' value='VD8mmvsbNI9bRhMpc0ILgSapBEQX9vmjKPWTdMZjh+PXJP68JS9Xg+n7\/KNrNyYSQdIqBTqcULlx9mmd19c+CeNevHSL09YYeqaHmhw4sPWPcMg=' \/>\n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_3' value='WyJ7XCIzLjFcIjpcIjdlMzA5YjYwNWIyNWE1MTEzZjVhOWM4OGQzZWI2NDllXCIsXCI0XCI6W1wiOTE5NzZhMWE2NDYwYzQzOTkzNWU2ZTVjMTAxNTJlY2FcIixcIjM0MzE3ODBjYjY4MTkwYjU2ZmE5NzJkNzc3N2ZlNzg1XCIsXCI4YTU0ZGVhNzEyYWMxM2Y5NzdmYzZhZTU5MmE5NjI2OVwiLFwiNmIwMjMxZDMwM2I3YjgzNzBmM2EyMGJmNzczZmNhYWZcIixcIjNmZGIwZTJkNjlmNTdlZTY1Mjk5Y2Q1Y2E3NThmNDgwXCJdfSIsIjEyZDA3YzAwOTgwY2VjMzUyYTJjZmY4ZDNlMmQzN2NhIl0=' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_target_page_number_3' id='gform_target_page_number_3' value='0' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_source_page_number_3' id='gform_source_page_number_3' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            \n        <\/div>\n                        <\/form>\n                        <\/div><script>\ngform.initializeOnLoaded( function() {gformInitSpinner( 3, 'https:\/\/arthroseactive.be\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', false );jQuery('#gform_ajax_frame_3').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_3');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_3').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){form_content.find('form').css('opacity', 0);jQuery('#gform_wrapper_3').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_3').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_3').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/  }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_3').val();gformInitSpinner( 3, 'https:\/\/arthroseactive.be\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', false );jQuery(document).trigger('gform_page_loaded', [3, current_page]);window['gf_submitting_3'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}jQuery('#gform_wrapper_3').replaceWith(confirmation_content);jQuery(document).trigger('gform_confirmation_loaded', [3]);window['gf_submitting_3'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_3').text());}else{jQuery('#gform_3').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger(\"gform_pre_post_render\", [{ formId: \"3\", currentPage: \"current_page\", abort: function() { this.preventDefault(); } }]);        if (event && event.defaultPrevented) {                return;        }        const gformWrapperDiv = document.getElementById( \"gform_wrapper_3\" );        if ( gformWrapperDiv ) {            const visibilitySpan = document.createElement( \"span\" );            visibilitySpan.id = \"gform_visibility_test_3\";            gformWrapperDiv.insertAdjacentElement( \"afterend\", visibilitySpan );        }        const visibilityTestDiv = document.getElementById( \"gform_visibility_test_3\" );        let postRenderFired = false;        function triggerPostRender() {            if ( postRenderFired ) {                return;            }            postRenderFired = true;            gform.core.triggerPostRenderEvents( 3, current_page );            if ( visibilityTestDiv ) {                visibilityTestDiv.parentNode.removeChild( visibilityTestDiv );            }        }        function debounce( func, wait, immediate ) {            var timeout;            return function() {                var context = this, args = arguments;                var later = function() {                    timeout = null;                    if ( !immediate ) func.apply( context, args );                };                var callNow = immediate && !timeout;                clearTimeout( timeout );                timeout = setTimeout( later, wait );                if ( callNow ) func.apply( context, args );            };        }        const debouncedTriggerPostRender = debounce( function() {            triggerPostRender();        }, 200 );        if ( visibilityTestDiv && visibilityTestDiv.offsetParent === null ) {            const observer = new MutationObserver( ( mutations ) => {                mutations.forEach( ( mutation ) => {                    if ( mutation.type === 'attributes' && visibilityTestDiv.offsetParent !== null ) {                        debouncedTriggerPostRender();                        observer.disconnect();                    }                });            });            observer.observe( document.body, {                attributes: true,                childList: false,                subtree: true,                attributeFilter: [ 'style', 'class' ],            });        } else {            triggerPostRender();        }    } );} );\n<\/script>\n\t\t\t<\/div>\n\n            <script type=\"text\/javascript\">\n                var gf_global = {\"gf_currency_config\":{\"name\":\"Euro\",\"symbol_left\":\"\",\"symbol_right\":\"&#8364;\",\"symbol_padding\":\" \",\"thousand_separator\":\".\",\"decimal_separator\":\",\",\"decimals\":2,\"code\":\"EUR\"},\"base_url\":\"https:\\\/\\\/arthroseactive.be\\\/wp-content\\\/plugins\\\/gravityforms\",\"number_formats\":[],\"spinnerUrl\":\"https:\\\/\\\/arthroseactive.be\\\/wp-content\\\/plugins\\\/gravityforms\\\/images\\\/spinner.svg\",\"version_hash\":\"68fcf36200bf86fa4972faebd92359e0\",\"strings\":{\"newRowAdded\":\"Nieuwe rij toegevoegd.\",\"rowRemoved\":\"Rij verwijderd\",\"formSaved\":\"Het formulier is opgeslagen. De inhoud bevat de link om terug te keren en het formulier in te vullen.\"}};\t\t\t\tvar gf_vars = {\"active\":\"Actief\",\"inactive\":\"Inactief\",\"save\":\"Opslaan\",\"update\":\"Bijwerken\",\"previousLabel\":\"Vorige\",\"selectFormat\":\"Selecteer een formaat\",\"column\":\"Kolom\",\"editToViewAll\":\"5 van %d items getoond. Wijzig veld om alles te bekijken\",\"selectAll\":\"Alles selecteren\",\"enterValue\":\"Voer een waarde in\",\"formTitle\":\"Formulier zonder titel\",\"formDescription\":\"We horen graag van je! Vul dit formulier in en we zullen binnenkort contact met je opnemen.\",\"formConfirmationMessage\":\"Bedankt voor je bericht! We zullen binnenkort contact met je opnemen.\",\"buttonText\":\"Versturen\",\"buttonDescription\":\"De verzendknop voor dit formulier\",\"loading\":\"Laden\\u2026\",\"thisFieldIf\":\"dit veld als\",\"thisSectionIf\":\"deze sectie als\",\"thisPage\":\"deze pagina als\",\"thisFormButton\":\"deze formulierknop als\",\"show\":\"Toon\",\"hide\":\"Verberg\",\"enable\":\"Inschakelen\",\"disable\":\"Uitschakelen\",\"enabled\":\"Ingeschakeld\",\"disabled\":\"Uitgeschakeld\",\"configure\":\"Configureren\",\"conditional_logic_text\":\"Voorwaardelijke logica\",\"conditional_logic_desc\":\"Met voorwaardelijke logica kan je wijzigen wat de gebruiker ziet, afhankelijk van de velden die ze selecteren.\",\"conditional_logic_a11y\":\"Het toevoegen van voorwaardelijke logica aan de knop voor het verzenden van formulieren kan voor sommige gebruikers toegankelijkheidsproblemen veroorzaken en een negatieve invloed hebben op het gebruik van je formulier. Lees meer over voorwaardelijke logica voor knoppen in onze <a href=\\\"https:\\\/\\\/docs.gravityforms.com\\\/field-accessibility-warning\\\/\\\" target=\\\"_blank\\\" rel=\\\"noopener\\\">documentatie<span class=\\\"screen-reader-text\\\">(opent in een nieuwe tab)<\\\/span>&nbsp;<span class=\\\"gform-icon gform-icon--external-link\\\" aria-hidden=\\\"true\\\"><\\\/span><\\\/a>.\",\"page\":\"Pagina\",\"next_button\":\"Volgende-knop\",\"button\":\"Verzendknop\",\"all\":\"Alles\",\"any\":\"Elke\",\"ofTheFollowingMatch\":\"van het volgende overeenkomt:\",\"is\":\"is\",\"isNot\":\"is niet\",\"greaterThan\":\"groter dan\",\"lessThan\":\"minder dan\",\"contains\":\"bevat\",\"startsWith\":\"start met\",\"endsWith\":\"eindigt met\",\"emptyChoice\":\"Leeg (geen geselecteere keuzes)\",\"alertLegacyMode\":\"Dit formulier heeft verouderde opmaak ingeschakeld en biedt geen ondersteuning voor het wijzigen van de grootte van velden in de editor. Schakel verouderde opmaak uit in de formulierinstellingen om live formaatwijziging in te schakelen.\",\"thisConfirmation\":\"Gebruik deze bevestiging als\",\"thisNotification\":\"Verstuur deze melding als\",\"confirmationSave\":\"Opslaan\",\"confirmationSaving\":\"Opslaan\\u2026\",\"confirmationAreYouSure\":\"Weet je zeker dat je deze wijzigingen wilt annuleren?\",\"confirmationIssueSaving\":\"Er was een probleem met het opslaan van deze bevestiging.\",\"confirmationConfirmDelete\":\"Weet je zeker dat je deze bevestiging wilt verwijderen?\",\"confirmationIssueDeleting\":\"Er was een probleem met het verwijderen van deze bevestiging.\",\"confirmationConfirmDiscard\":\"Er zijn niet-opgeslagen wijzigingen voor de huidige bevestiging. Wil je deze wijzigingen verwerpen?\",\"confirmationDefaultName\":\"Bevestiging zonder titel\",\"confirmationDefaultMessage\":\"Bedankt voor je bericht! We zullen binnenkort contact met je opnemen.\",\"confirmationInvalidPageSelection\":\"Selecteer een pagina.\",\"confirmationInvalidRedirect\":\"Voer een URL in.\",\"confirmationInvalidName\":\"Voer een bevestigingsnaam in.\",\"confirmationDeleteField\":\"Als je dit veld verwijdert, worden ook alle bijbehorende invoergegevens verwijderd. Annuleren' om af te breken. OK' om te verwijderen.\",\"confirmationDeleteDisplayField\":\"Je staat op het punt dit veld te verwijderen. 'Annuleren' om te stoppen. 'OK' om te verwijderen\",\"confirmationDeleteDisplayFieldTitle\":\"Waarschuwing\",\"conditionalLogicDependency\":\"Dit formulier bevat {type} voorwaardelijke logica afhankelijk van dit veld. Het verwijderen van dit veld zal die voorwaardelijke logica regels deactiveren en ook alle invoergegevens die aan het veld zijn gekoppeld verwijderen. 'Annuleren' om af te breken. 'OK' om te verwijderen.\",\"conditionalLogicDependencyChoice\":\"Dit formulier bevat {type} voorwaardelijke logica afhankelijk van deze keuze. Weet je zeker dat je deze keuze wil verwijderen? 'Annuleren' om af te breken. 'OK' om te verwijderen.\",\"conditionalLogicDependencyChoiceEdit\":\"Dit formulier bevat {type} voorwaardelijke logica afhankelijk van deze keuze. Weet je zeker dat je deze keuze wil wijzigen? 'Annuleren' om af te breken. 'OK' om door te gaan.\",\"conditionalLogicDependencyAdminOnly\":\"Dit formulier bevat {type} voorwaardelijke logica afhankelijk van dit veld. Weet je zeker dat je dit veld als Administratief wil markeren? 'Annuleren' om af te breken. 'OK' om door te gaan.\",\"conditionalLogicRichTextEditorWarning\":\"Dit formulier bevat conditionele logica afhankelijk van dit veld. Dit zal niet meer werken als de Rich Text Editor is ingeschakeld. Weet je zeker dat je de Rich Text Editor wil inschakelen? 'Annuleren' om af te breken. 'OK' om door te gaan.\",\"conditionalLogicTypeButton\":\"knop\",\"conditionalLogicTypeConfirmation\":\"bevestiging\",\"conditionalLogicTypeNotification\":\"melding\",\"conditionalLogicTypeNoficationRouting\":\"melding routering\",\"conditionalLogicTypeField\":\"veld\",\"conditionalLogicTypeFeed\":\"feed\",\"conditionalLogicWarningTitle\":\"Waarschuwing voor voorwaardelijke logica\",\"mergeTagsText\":\"Voeg samenvoeg tags in\",\"baseUrl\":\"https:\\\/\\\/arthroseactive.be\\\/wp-content\\\/plugins\\\/gravityforms\",\"gf_currency_config\":{\"name\":\"Euro\",\"symbol_left\":\"\",\"symbol_right\":\"&#8364;\",\"symbol_padding\":\" \",\"thousand_separator\":\".\",\"decimal_separator\":\",\",\"decimals\":2,\"code\":\"EUR\"},\"otherChoiceValue\":\"Anders\",\"isFormTrash\":false,\"currentlyAddingField\":false,\"visibilityOptions\":[{\"label\":\"Zichtbaar\",\"value\":\"visible\",\"description\":\"Standaardoptie. Het veld is zichtbaar bij het bekijken van het formulier.\"},{\"label\":\"Verborgen\",\"value\":\"hidden\",\"description\":\"Het veld is verborgen bij het bekijken van het formulier. Nuttig wanneer je de functionaliteit van dit veld nodig hebt, maar niet wilt dat de gebruiker dit veld ziet.\"},{\"label\":\"Administratief\",\"value\":\"administrative\",\"description\":\"Het veld is alleen zichtbaar bij het beheren van verzonden inzendingen. Het veld is niet zichtbaar of functioneel bij het bekijken van het formulier.\"}],\"addFieldFilter\":\"Voorwaarde toevoegen\",\"removeFieldFilter\":\"Voorwaarde verwijderen\",\"filterAndAny\":\"{0} van de volgende overeenkomst:\",\"customChoices\":\"Aangepaste keuzes\",\"predefinedChoices\":\"Voorgedefinieerde keuzes\",\"fieldLabelAriaLabel\":\"{field_label} - {field_type}, spring naar de instellingen van dit veld\",\"fieldCanBeAddedTitle\":\"Veldlimiet\",\"fieldCanBeAddedCaptcha\":\"Een formulier kan slechts \\u00e9\\u00e9n CAPTCHA veld bevatten.\",\"fieldCanBeAddedShipping\":\"Een formulier kan slechts \\u00e9\\u00e9n verzend veld bevatten.\",\"fieldCanBeAddedPostContent\":\"Een formulier kan slechts \\u00e9\\u00e9n bericht body veld bevatten.\",\"fieldCanBeAddedPostTitle\":\"Een formulier kan slechts \\u00e9\\u00e9n bericht titelveld bevatten.\",\"fieldCanBeAddedPostExcerpt\":\"Een formulier kan slechts \\u00e9\\u00e9n bericht samenvattingsveld bevatten.\",\"fieldCanBeAddedCreditCard\":\"Een formulier kan slechts \\u00e9\\u00e9n creditcard veld bevatten.\",\"fieldCanBeAddedProductTitle\":\"Ontbrekend productveld\",\"fieldCanBeAddedProduct\":\"Je moet eerst een product veld aan het formulier toevoegen\",\"legacyMarkupTitle\":\"Ongeldige lay-out\",\"fieldCanBeAddedMultipleChoice\":\"Je kunt geen multiple choice veld toevoegen aan een formulier dat legacy lay-out gebruikt. Bewerk de formulierinstellingen en schakel legacy mark-up uit.\",\"fieldCanBeAddedImageChoice\":\"Je kunt geen afbeelding keuzeveld toevoegen aan een formulier dat legacy lay-out gebruikt. Bewerk de formulierinstellingen en schakel legacy lay-out uit.\",\"FieldAjaxonErrorTitle\":\"Fout\",\"StartAddFieldAjaxonError\":\"Ajax fout bij het toevoegen van veld. Ververs de pagina en probeer het opnieuw.\",\"StartChangeInputTypeAjaxonError\":\"Ajax fout bij het wijzigen van het invoertype. Ververs de pagina en probeer het opnieuw.\",\"MissingNameCustomChoicesTitle\":\"Naam ontbreekt\",\"MissingNameCustomChoices\":\"Geef deze aangepaste keuze een naam.\",\"DuplicateNameCustomChoicesTitle\":\"Dubbele naam\",\"DuplicateNameCustomChoices\":\"Deze aangepaste keuzenaam is al in gebruik. Voer een andere naam in.\",\"DuplicateTitleMessageTitle\":\"Dubbele titel\",\"DuplicateTitleMessage\":\"De ingevoerde titel van het formulier is al in gebruik. Voer een unieke titel voor het formulier in.\",\"ValidateFormMissingFormTitleTitle\":\"Ontbrekende formulier titel\",\"ValidateFormMissingFormTitle\":\"Voer een Titel voor dit formulier in. Wanneer het formulier wordt toegevoegd aan een pagina of bericht, heb je de optie om de titel te verbergen.\",\"ValidateFormEmptyPageTitle\":\"Lege pagina\",\"ValidateFormEmptyPage\":\"Dit formulier heeft op dit moment \\u00e9\\u00e9n of meer pagina&#039;s zonder velden. Blanco pagina&#039;s zijn het gevolg van paginascheidingen die als eerste of laatste veld in het formulier of vlak na elkaar staan. Pas het pagina einde aan.\",\"ValidateFormMissingProductLabelTitle\":\"Ontbrekend productlabel\",\"ValidateFormMissingProductLabel\":\"Dit formulier heeft een productveld met een lege label. Voer een label in voor elk productveld.\",\"ValidateFormMissingProductFieldTitle\":\"Ontbrekend productveld\",\"ValidateFormMissingProductField\":\"Dit formulier heeft een optie veld zonder een product veld. Je moet een product veld toevoegen aan je formulier.\",\"FormulaIsValidTitle\":\"Succes\",\"FormulaIsValid\":\"De formule lijkt geldig te zijn.\",\"FormulaIsInvalid\":\"Er lijkt een probleem met de formule te zijn.\",\"DeleteFormTitle\":\"Bevestigen\",\"DeleteForm\":\"Je staat op het punt dit formulier naar de prullenbak te verplaatsen. &#039;Annuleren&#039; om te stoppen. &#039;OK&#039; om te verwijderen.\",\"DeleteCustomChoice\":\"Deze aangepaste keuzelijst verwijderen? &#039;Annuleren&#039; om te stoppen. &#039;OK&#039; om te verwijderen.\",\"FieldAdded\":\"&nbsp;veld toegevoegd aan formulier\",\"nameFieldDefaultPrefixes\":[{\"text\":\"Dr.\",\"value\":\"Dr.\"},{\"text\":\"Ds.\",\"value\":\"Ds.\"},{\"text\":\"Mevr.\",\"value\":\"Mevr.\"},{\"text\":\"Mr.,Dhr.\",\"value\":\"Mr.,Dhr.\"},{\"text\":\"Ms.\",\"value\":\"Ms.\"},{\"text\":\"Prof.\",\"value\":\"Prof.\"}]};\t\t\t<\/script>\n            \t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb7c11d elementor-widget elementor-widget-spacer\" data-id=\"bb7c11d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0b6bc02 elementor-absolute elementor-hidden-mobile elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"0b6bc02\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"171\" height=\"153\" viewBox=\"0 0 171 153\" fill=\"none\"><path d=\"M156.15 135.795C155.944 135.847 155.757 135.906 155.558 135.94C155.377 135.98 155.197 136.02 155.016 136.06C154.662 136.122 154.344 136.196 154.039 136.234C153.735 136.272 153.449 136.317 153.169 136.343C152.89 136.368 152.61 136.394 152.349 136.427C151.256 136.518 150.15 136.647 148.39 136.919C147.539 136.972 146.657 137.055 145.787 137.163C144.911 137.228 144.035 137.292 143.197 137.37C142.803 137.543 142.263 137.539 141.68 137.541C141.389 137.542 141.097 137.542 140.824 137.55C140.551 137.557 140.272 137.583 140.041 137.647L139.673 137.454C139.348 137.548 138.957 137.596 138.643 137.485L138.662 137.43C138.176 137.57 137.639 137.442 137.39 137.5L137.409 137.444L136.833 137.427L136.939 137.361C136.504 137.415 136.089 137.414 135.655 137.406C135.227 137.379 134.832 137.323 134.442 137.247L134.481 137.49C134.08 137.389 133.728 137.327 133.424 137.303C133.263 137.288 133.121 137.279 132.978 137.27C132.836 137.261 132.693 137.253 132.569 137.25C132.018 137.222 131.51 137.187 130.789 136.932L130.809 136.877C130.566 136.916 130.349 136.943 130.126 136.926C129.921 136.917 129.705 136.882 129.507 136.853C129.117 136.778 128.766 136.654 128.39 136.541C128.205 136.476 128.039 136.417 127.854 136.352C127.669 136.286 127.484 136.221 127.293 136.174C126.91 136.08 126.471 136.029 125.962 136.056C126.216 136.043 125.884 135.925 125.922 135.876C125.482 135.824 125.026 135.704 124.679 135.686C124.313 135.66 124.064 135.718 123.992 135.921C123.369 135.742 123.507 135.646 123.492 135.453C123.427 135.638 122.863 135.584 122.376 135.433L122.624 135.437L121.217 135.064L121.377 135.495C120.663 135.16 121.324 134.998 120.601 134.867L120.496 135.163C119.517 134.754 119.089 134.083 118.207 133.521C117.721 133.307 117.216 133.087 116.724 132.892C116.465 132.8 116.213 132.69 115.96 132.58C115.702 132.489 115.456 132.36 115.204 132.25C114.699 132.03 114.188 131.828 113.684 131.608C113.179 131.388 112.681 131.149 112.202 130.917C111.199 130.459 110.267 129.921 109.359 129.371C109.236 129.306 109.138 129.23 109.016 129.166C108.899 129.083 108.801 129.007 108.697 128.949C108.483 128.79 108.287 128.638 108.073 128.479C107.663 128.167 107.279 127.844 106.9 127.502L106.9 127.211C107.036 126.884 105.745 126.948 105.8 126.614L105.338 126.45C105.279 126.325 105.084 126.111 105.324 126.196C105.166 126.056 105.061 125.998 104.969 125.966C104.876 125.933 104.803 125.907 104.636 125.848L104.421 125.398C104.129 125.107 103.811 124.828 103.5 124.593C103.334 124.472 103.188 124.358 103.022 124.237L102.552 123.862C102.24 123.627 101.934 123.373 101.61 123.113C101.452 122.974 101.287 122.853 101.134 122.695C100.976 122.556 100.83 122.379 100.678 122.222C100.383 121.763 99.9763 121.266 99.496 120.742C99.0407 120.207 98.518 119.627 97.9888 119.065C96.9435 117.904 95.8482 116.768 95.1082 115.861C94.8225 115.552 94.5552 115.249 94.3009 114.91C94.0717 114.558 93.8491 114.188 93.633 113.8C93.4353 113.418 93.2192 113.029 93.0282 112.629C92.8621 112.216 92.6961 111.804 92.5235 111.41C92.3574 110.998 92.1848 110.604 92.0187 110.191C91.8712 109.785 91.705 109.373 91.539 108.961C91.4619 108.767 91.3664 108.567 91.2709 108.366C91.1753 108.166 91.0733 107.985 90.9963 107.791C90.8171 107.415 90.6194 107.033 90.3902 106.682C90.3925 106.558 90.1981 106.343 90.148 106.367C90.0656 106.13 89.9581 105.905 89.8822 105.649L89.6598 104.926L89.1901 103.49C89.1901 103.49 89.1662 103.44 89.1435 103.328C89.1142 103.235 89.086 103.079 89.0274 102.892C88.9287 102.524 88.7769 102.013 88.6012 101.451C88.548 101.308 88.5134 101.171 88.4667 101.008C88.4201 100.846 88.392 100.691 88.3388 100.547C88.264 100.229 88.1707 99.9051 88.0959 99.5874C88.0027 99.2631 87.9094 98.9389 87.8281 98.6397C87.7468 98.3405 87.672 98.0227 87.5961 97.767C87.2816 96.6572 86.93 95.8879 86.5719 96.1356C86.4021 96.2628 86.2343 96.6195 86.0597 97.3483C85.9723 97.7126 85.8958 98.164 85.8235 98.7209C85.7512 99.2779 85.7333 99.9164 85.7131 100.679L85.6338 100.609C85.6878 101.044 85.7113 101.448 85.7915 101.809C85.8717 102.171 85.9399 102.507 86.0397 102.812C86.1395 103.118 86.2393 103.424 86.3707 103.699C86.502 103.975 86.6334 104.25 86.8333 104.508C86.4676 104.836 87.2607 105.887 87.2527 106.321L87.1972 106.301C87.5177 106.747 87.6815 107.284 87.8268 107.814C87.9721 108.343 88.0923 108.885 88.4444 109.301C88.3889 109.281 88.2768 109.304 88.1628 109.097C88.2464 109.273 88.3485 109.454 88.4506 109.636C88.5527 109.818 88.6362 109.993 88.7264 110.15C88.8816 110.475 88.9576 110.731 88.8629 110.822C88.9584 111.022 89.0725 111.229 89.18 111.454C89.2277 111.555 89.2874 111.68 89.3537 111.786C89.4199 111.893 89.4862 112 89.5459 112.125C89.8044 112.57 90.0563 113.034 90.3028 113.454C90.4354 113.667 90.5678 113.88 90.6819 114.087C90.8209 114.282 90.96 114.477 91.0936 114.628C91.3663 114.974 91.6217 115.252 91.8662 115.442L91.7738 115.41C92.0738 115.62 92.1825 115.783 92.2965 115.99C92.392 116.19 92.5126 116.378 92.793 116.644C92.7734 116.699 92.7973 116.749 92.7788 116.743C93.0973 116.96 93.4058 117.381 93.6959 117.796C93.8284 118.009 93.9674 118.204 94.088 118.392C94.2151 118.562 94.3488 118.713 94.4585 118.814L94.3507 118.943L95.2547 120.032L94.9527 119.592C95.4455 119.434 95.3673 120.655 96.2935 121.211C96.5966 121.589 97.1011 121.809 97.5871 122.022C97.8209 122.126 98.0731 122.236 98.3003 122.358C98.521 122.499 98.6982 122.644 98.8307 122.858C99.3297 123.034 98.2858 122.811 98.8989 123.194C98.728 123.383 98.5477 123.07 98.5366 123.336C98.8181 123.54 98.9745 123.803 99.1559 124.055C99.3308 124.325 99.5307 124.582 99.9047 124.819L99.8022 124.991C100.337 125.242 100.671 125.652 100.992 126.036C101.295 126.414 101.593 126.748 101.988 126.867C102.975 127.486 102.212 127.82 103.394 128.3L103.615 128.794C104.011 129.143 104.105 128.76 104.488 129.207C104.361 129.329 104.998 129.762 104.634 129.675C105.077 130.186 105.686 130.463 106.331 130.816C106.644 130.99 106.976 131.169 107.287 131.405C107.599 131.64 107.936 131.863 108.259 132.185C108.744 132.107 109.384 132.708 109.758 132.653C109.705 132.801 111.268 133.499 110.254 133.307C110.18 133.281 110.032 133.229 110.07 133.18L109.864 133.294C110.204 133.685 110.622 133.853 111.072 133.992C111.294 134.07 111.504 134.124 111.732 134.184C111.954 134.262 112.176 134.341 112.385 134.456C112.152 134.291 111.802 134.105 112.094 134.104C112.351 134.257 112.622 134.374 112.905 134.515L112.656 134.573L113.834 135.24L113.758 134.984C114.028 135.162 114.185 135.364 114.374 135.535C114.57 135.687 114.779 135.803 115.188 135.823C115.566 135.811 114.719 135.324 115.391 135.541C115.765 135.777 116.244 136.071 116.74 136.372C116.998 136.525 117.262 136.661 117.526 136.796C117.791 136.931 118.061 137.047 118.313 137.157C118.3 136.903 118.57 137.019 118.879 137.087L118.851 137.285C120.063 137.444 119.107 137.854 120.319 138.013L120.181 138.109L120.614 137.826C121.75 137.791 121.038 138.392 122.318 138.242C121.855 138.14 122.234 137.775 122.757 138.001L122.562 138.141C122.878 138.19 123.003 138.13 123.193 138.239C122.987 138.291 123.027 138.472 123.491 138.573L123.128 138.715L124.079 138.615C124.686 139.017 125.803 138.975 126.02 139.302C126.02 139.302 126.371 139.426 126.779 139.508C126.97 139.555 127.187 139.59 127.373 139.593C127.559 139.596 127.726 139.593 127.814 139.52C127.484 139.632 128.273 139.87 128.01 140.026C128.427 139.904 129.562 139.931 129.972 140.242L129.885 140.253C130.692 140.497 131.411 140.523 132.112 140.542C132.279 140.539 132.459 140.561 132.626 140.557C132.794 140.554 132.973 140.576 133.134 140.591C133.481 140.61 133.833 140.672 134.191 140.778C134.146 140.554 134.93 140.748 134.75 140.435C134.942 140.42 135.128 140.423 135.314 140.427C135.5 140.43 135.679 140.452 135.834 140.486C136.168 140.541 136.495 140.616 136.767 140.67C137.336 140.767 137.8 140.807 138.1 140.372C138.795 140.347 138.914 140.598 139.285 140.667L139.123 140.713C139.774 140.694 140.196 140.677 140.587 140.69C140.965 140.679 141.3 140.672 141.796 140.681C142.288 140.585 142.351 140.171 143.212 140.267C142.923 140.435 143.283 140.417 143.6 140.404C143.401 140.438 143.338 140.499 143.764 140.587C143.827 140.526 143.921 140.497 143.996 140.461C143.996 140.461 144.014 140.468 144.001 140.505C144.548 140.428 144.444 140.37 144.196 140.365C144.202 140.347 144.197 140.303 144.105 140.271C144.678 140.474 145.675 140.182 145.745 140.456C146.565 140.372 147.244 140.216 147.897 140.073C148.551 139.93 149.175 139.756 149.822 139.631C149.987 139.752 149.699 139.92 149.306 140.031C149.617 139.974 149.947 139.925 150.258 139.868C150.285 140.086 149.733 140.057 149.434 140.139C150.021 140.242 150.601 140.073 151.2 139.91C151.805 139.729 152.416 139.529 153.116 139.548L153.362 139.323L153.436 139.35C153.432 139.244 153.702 139.069 153.889 139.01C154.11 139.151 153.968 139.434 154.628 139.272C154.907 139.308 155.281 139.191 155.65 139.03C155.844 138.953 156.019 138.869 156.219 138.774C156.394 138.69 156.576 138.588 156.745 138.523C156.383 138.603 156.473 138.468 156.593 138.365C156.917 138.272 157.15 138.375 157.37 138.224L157.478 138.45C157.289 138.279 158.225 137.924 158.315 137.789C158.567 137.899 157.869 138.109 157.835 138.264C159.121 137.803 158.478 138.034 159.746 137.505C160.344 137.05 159.532 137.346 159.774 137.015C160.338 136.715 160.817 136.302 161.522 136.073L161.226 135.969C161.471 135.806 161.684 135.673 161.879 135.534C162.074 135.395 162.262 135.274 162.444 135.172C162.826 134.974 163.157 134.801 163.538 134.665C164.322 133.86 164.813 133.119 165.14 132.548C165.211 132.407 165.3 132.272 165.364 132.149C165.41 132.019 165.474 131.897 165.514 131.786C165.592 131.564 165.658 131.379 165.71 131.231C165.778 130.922 165.763 130.73 165.671 130.635C165.58 130.54 165.456 130.538 165.275 130.578C165.095 130.618 164.895 130.714 164.706 130.834C164.606 130.882 164.5 130.948 164.411 131.021C164.305 131.087 164.217 131.16 164.117 131.208C163.722 131.443 163.432 131.673 163.432 131.673C163.112 131.872 162.799 132.052 162.522 132.246C162.227 132.433 161.964 132.589 161.713 132.771C161.656 132.813 161.581 132.849 161.518 132.91C161.461 132.952 161.386 132.988 161.329 133.03C161.198 133.109 161.066 133.187 160.946 133.29C160.815 133.368 160.695 133.472 160.563 133.55C160.432 133.628 160.3 133.706 160.18 133.81C159.151 134.485 157.996 135.221 156.186 135.87L156.15 135.795Z\" fill=\"#2D2C78\"><\/path><path d=\"M161.985 141.583C162.916 140.54 163.481 140.47 164.187 139.18C164.613 138.623 164.936 137.947 165.269 137.357C165.159 136.903 165.742 136.609 165.701 136.137L165.937 136.117C165.934 135.949 165.949 135.788 166.093 135.735L166.148 135.754C166.121 135.537 166.297 135.391 166.3 135.267L166.355 135.287L166.445 135.09L166.5 135.172C166.514 135.073 166.522 134.992 166.554 134.9C166.568 134.863 166.581 134.826 166.6 134.77L166.626 134.696L166.659 134.604C166.788 134.358 166.928 134.137 167.087 133.923L166.852 133.882C167.03 133.674 167.157 133.49 167.259 133.319C167.343 133.14 167.402 132.974 167.461 132.807C167.579 132.475 167.671 132.216 168.089 131.74L168.144 131.759C168.112 131.498 168.172 131.27 168.294 131.042C168.339 130.913 168.434 130.822 168.523 130.687L168.651 130.503L168.727 130.405L168.734 130.387L168.697 130.374C168.525 130.271 168.353 130.169 168.094 130.077C167.836 129.986 167.495 129.949 167.055 129.959C167.284 129.957 167.094 129.848 167.169 129.812C166.842 129.738 166.526 129.689 166.241 129.671C165.95 129.672 165.726 129.718 165.573 129.913C165.222 129.789 165.354 129.711 165.394 129.538C165.273 129.703 164.901 129.696 164.618 129.617L164.773 129.589L164.328 129.494C164.254 129.468 164.217 129.454 164.155 129.453L164.026 129.408C164.019 129.426 164.025 129.823 164.025 129.823C163.755 129.645 164.083 129.365 163.766 129.378L163.661 129.674C163.305 129.506 163.196 128.989 162.855 128.66C161.272 128.079 159.326 128.348 157.979 127.393L157.977 127.163C158.033 126.829 157.431 127.532 157.462 127.21L157.243 127.299C157.207 127.224 157.134 127.136 157.234 127.088C157.068 127.029 157.049 127.084 156.923 127.144L156.804 126.894C156.215 126.56 155.553 126.784 154.919 126.518C154.23 125.879 152.607 125.825 151.658 125.801C150.297 125.944 149.231 124.256 147.813 124.441C147.789 124.391 147.639 124.462 147.651 124.487L146.511 124.125C146.511 124.125 140.954 122.43 144.449 126.308L144.423 126.382C144.987 126.728 145.368 126.883 145.912 126.639C145.854 127.097 146.43 126.822 146.525 127.022L146.512 127.059C146.988 126.832 147.21 127.556 147.673 127.366C147.66 127.403 147.62 127.514 147.521 127.5C147.806 127.517 148.197 127.531 148.149 127.784C148.816 127.895 149.684 128.265 150.198 127.989L150.172 128.063C150.455 127.851 150.468 128.105 150.761 128.043C150.748 128.08 150.778 128.111 150.778 128.111C151.117 127.919 151.532 128.274 151.781 128.216L151.722 128.383C151.741 128.389 152.266 128.492 152.266 128.492L152.081 128.426C152.288 127.959 152.384 128.804 152.847 128.614C153.185 128.775 153.822 127.857 154.12 128.191C154.346 128.021 153.866 128.496 154.172 128.396C154.105 128.643 154.008 128.505 154.017 128.716C154.303 128.672 154.364 129.088 154.725 129.008L154.659 129.193C155.197 128.967 155.389 129.659 155.747 129.411C156.219 129.37 155.871 130.059 156.415 129.814L156.515 130.12C156.687 130.223 156.737 129.845 156.901 130.028C156.842 130.194 157.121 130.23 156.958 130.339C157.36 130.731 158.007 130.253 158.505 130.845C158.727 130.57 158.982 130.848 159.16 130.64C159.133 130.776 159.77 130.856 159.351 131.04C159.307 131.046 159.27 131.033 159.284 130.996L159.181 131.167C159.44 131.613 159.87 131.161 160.214 131.304C160.123 131.209 159.987 131.182 160.125 131.085L160.44 131.197L160.325 131.343L160.786 131.569L160.778 131.358C160.992 131.517 160.973 131.864 161.311 131.672C161.475 131.563 161.156 131.346 161.423 131.357C161.698 131.579 162.119 131.916 162.501 132.072C162.517 131.849 162.628 131.888 162.759 131.872L162.693 132.057C163.217 131.93 162.759 132.517 163.245 132.439L163.162 132.555L163.392 132.2C163.448 132.157 163.492 132.152 163.535 132.146C163.535 132.146 163.535 132.146 163.554 132.153C163.554 132.153 163.553 132.215 163.54 132.252C163.513 132.326 163.487 132.4 163.671 132.174C163.603 132.191 163.834 131.773 163.9 131.88C163.862 131.929 163.817 131.996 163.779 132.045C163.829 132.021 163.911 131.967 163.898 132.004C163.809 132.077 163.714 132.23 163.782 132.213C163.719 132.274 163.656 132.335 163.593 132.396C163.687 132.304 163.801 132.219 163.914 132.135C163.881 132.227 163.925 132.222 163.962 132.235C163.999 132.248 164.036 132.261 163.916 132.364C163.916 132.364 163.903 132.401 163.946 132.396C163.983 132.409 164.077 132.38 164.295 132.291C164.152 132.344 164.077 132.38 163.995 132.434C163.895 132.482 163.795 132.53 163.645 132.601C163.788 132.548 163.925 132.513 163.962 132.526C163.999 132.539 163.968 132.57 163.824 132.623L163.806 132.617C163.631 132.7 163.736 132.696 163.785 132.734C163.822 132.747 163.84 132.754 163.839 132.816C163.826 132.853 163.795 132.883 163.701 132.912C163.923 132.991 163.761 133.038 164.045 133.117C164.068 133.167 164.062 133.186 164.049 133.223L164.036 133.26C164.036 133.26 164.016 133.315 163.973 133.32C163.878 133.412 163.79 133.485 163.702 133.557C163.525 133.703 163.454 133.844 163.777 134.167C163.692 134.407 163.433 134.316 163.339 134.407L163.328 134.32C163.146 134.775 163.082 134.898 162.878 135.18C162.849 135.378 163.198 135.626 162.934 135.845C162.85 135.669 162.804 135.799 162.747 135.903C162.773 135.829 162.731 135.773 162.562 135.838C162.586 135.888 162.591 135.931 162.597 135.975C162.597 135.975 162.578 135.968 162.56 135.962C162.488 136.165 162.556 136.148 162.638 136.094C162.656 136.1 162.693 136.113 162.749 136.133C162.456 136.196 162.448 136.63 162.184 136.495C161.914 137.023 161.91 137.563 161.703 138.03C161.555 137.978 161.508 137.816 161.542 137.661L161.388 137.981C161.222 137.86 161.411 137.74 161.431 137.622C160.92 137.774 161.21 138.542 160.66 138.743L160.744 138.918L160.707 138.905C160.768 138.969 160.796 139.124 160.788 139.205C160.603 139.139 160.439 138.956 160.305 139.159C160.038 139.209 160.048 139.65 159.975 139.915C160.088 139.831 160.136 139.931 160.154 139.999C160.077 140.097 159.886 140.05 159.909 140.162L159.706 140.028C159.922 140.125 159.705 140.444 159.759 140.526C159.574 140.46 159.745 140.271 159.661 140.158C159.374 140.556 159.527 140.36 159.24 140.758C159.228 141.087 159.449 140.873 159.538 141.092C159.441 141.308 159.423 141.593 159.136 141.699L159.358 141.777C159.201 142.221 159.03 142.41 158.669 142.491C158.491 143.405 158.449 143.994 158.541 144.38C158.633 144.766 158.835 144.9 159.045 144.954C159.497 145.03 160.056 144.625 160.056 144.625C161.303 143.922 161.246 142.966 162.084 141.598L161.985 141.583Z\" fill=\"#2D2C78\"><\/path><path d=\"M60.5758 59.4732C60.5812 59.4938 60.5448 59.4813 60.4667 59.4357C60.419 59.3379 60.3278 59.2846 60.1932 59.2758C60.1519 59.2866 60.134 59.3024 60.1394 59.323C60.1502 59.3643 60.1192 59.3724 60.0465 59.3474C60.0465 59.3474 60.0362 59.3501 60.0156 59.3555C59.9949 59.3609 59.9873 59.3739 59.9927 59.3946C60.0296 59.451 60.0122 59.5108 59.9405 59.5737C59.8329 59.6681 59.7373 59.6821 59.6538 59.6158C59.6017 59.5853 59.5344 59.5809 59.4518 59.6026L59.4127 59.5798L59.3818 59.5879C59.3513 59.64 59.2998 59.6535 59.227 59.6285L59.0479 59.5762C59.0219 59.561 59.0115 59.5637 59.017 59.5843C58.955 59.6006 58.9084 59.5908 58.8769 59.5549L58.7582 59.3545L58.7191 59.3316C58.6985 59.337 58.6881 59.3397 58.6881 59.3397C58.6936 59.3604 58.6963 59.3707 58.6963 59.3707C58.6919 59.438 58.6636 59.4565 58.6115 59.426C58.5486 59.3543 58.5144 59.3081 58.509 59.2875L58.335 59.0023C58.2091 58.8589 58.1137 58.6633 58.0488 58.4157C57.9642 58.2615 57.9111 58.1431 57.8895 58.0605L57.6652 57.4577C57.5894 57.1688 57.5223 56.9548 57.4637 56.8158L57.1243 55.6477L56.9634 55.1606L56.7036 54.1701C56.6559 54.0723 56.624 53.9925 56.6077 53.9306C56.6067 53.8426 56.5981 53.7677 56.5818 53.7058C56.5125 53.5255 56.4237 53.229 56.3154 52.8163C56.2732 52.7391 56.2439 52.6696 56.2277 52.6077C56.2321 52.5404 56.2288 52.4861 56.218 52.4448L56.0998 51.6157L56.0125 50.7784C55.9746 50.634 55.9552 50.5178 55.9542 50.4298L55.9136 50.2751C55.9028 50.2338 55.8767 50.2186 55.8354 50.2294L55.6969 50.3319L55.0499 50.7663C55.0141 50.7977 54.9679 50.8319 54.9114 50.8688C54.8755 50.9002 54.8294 50.9344 54.7729 50.9713C54.7577 50.9973 54.7088 51.0212 54.6262 51.0428C54.5437 51.0645 54.4796 51.1144 54.4339 51.1925L54.3263 51.2869L54.2644 51.3031C54.2536 51.2618 54.2558 51.2282 54.271 51.2021C54.2863 51.1761 54.3015 51.15 54.3167 51.124C54.3526 51.0925 54.3987 51.0584 54.4552 51.0215L54.5856 50.888C54.6161 50.836 54.6878 50.773 54.8008 50.6993L55.1235 50.4161L55.1773 50.369L55.1154 50.3852C55.0589 50.4221 54.9948 50.472 54.9231 50.5349C54.8514 50.5978 54.7693 50.6634 54.677 50.7318L54.2614 51.0393C54.2408 51.0447 54.1767 51.0946 54.0691 51.1889L54.0072 51.2052L53.9453 51.2214C53.9399 51.2008 53.9371 51.1905 53.9371 51.1905C53.9578 51.1851 53.9681 51.1824 53.9681 51.1824L54.0219 51.1352L54.0366 51.0651L53.9747 51.0814L53.5282 51.397C53.5129 51.423 53.4874 51.4518 53.4515 51.4833C53.4363 51.5093 53.4081 51.5277 53.3668 51.5386C53.3516 51.5646 53.3233 51.583 53.2821 51.5939L53.2968 51.5238L53.3115 51.4538L53.2577 51.501L52.9431 51.8151C52.8464 51.9508 52.7285 52.0478 52.5894 52.1064C52.5482 52.1172 52.5096 52.1383 52.4737 52.1698C52.4585 52.1958 52.4433 52.2219 52.4281 52.2479C52.3672 52.3521 52.2927 52.4047 52.2048 52.4057C52.1787 52.3905 52.176 52.3802 52.1967 52.3748C52.1859 52.3335 52.2011 52.3075 52.2423 52.2967L52.2261 52.2347L52.1952 52.2429L52.1642 52.251L52.1023 52.2672L52.1332 52.2591L52.5082 51.7968L52.5392 51.7887C52.5338 51.7681 52.5208 51.7605 52.5001 51.7659C52.4643 51.7973 52.4284 51.8288 52.3925 51.8603C52.3773 51.8863 52.3388 51.9075 52.2769 51.9237C52.1486 52.0235 52.0595 52.1461 52.0094 52.2916C51.9746 52.411 51.9496 52.4837 51.9343 52.5098C51.8843 52.6552 51.8364 52.767 51.7907 52.8452L51.7547 53.0862L51.6568 53.3435L51.3924 53.9752L51.2112 54.4197L51.1427 54.5369C51.1275 54.563 51.0824 54.6851 51.0073 54.9033C50.9974 54.95 51.0034 55.0146 51.025 55.0971L51.0331 55.1281C51.0592 55.1433 51.0646 55.1639 51.0494 55.19C51.0548 55.2106 51.0423 55.247 51.0118 55.2991C50.9966 55.3251 50.958 55.3463 50.8961 55.3625C50.8342 55.3787 50.793 55.3896 50.7723 55.395C50.7256 55.3852 50.6762 55.365 50.6242 55.3346C50.5927 55.2987 50.5563 55.2862 50.5151 55.2971L50.4222 55.3214L50.1989 55.4792L50.1061 55.5036L49.9204 55.5523C49.853 55.5479 49.7803 55.5229 49.7022 55.4772C49.624 55.4315 49.5616 55.4038 49.5149 55.394C49.4368 55.3483 49.3564 55.3363 49.2739 55.3579C49.1501 55.3904 49.041 55.3529 48.9466 55.2453C48.9097 55.1888 48.8598 55.1247 48.7969 55.053C48.7079 54.966 48.6423 54.884 48.6 54.8069C48.5892 54.7656 48.5757 54.714 48.5594 54.6521C48.5226 54.5956 48.5036 54.5234 48.5026 54.4354C48.5006 54.2595 48.4887 54.1303 48.4671 54.0478C48.463 53.6959 48.4806 53.4267 48.5199 53.2399C48.5297 53.1933 48.5743 53.0272 48.6538 52.7416L48.9182 52.1099C48.953 51.9905 48.9982 51.8684 49.0537 51.7435C49.1092 51.6187 49.1543 51.4966 49.1892 51.3772L49.3475 50.9718C49.4486 50.7688 49.5743 50.4491 49.7245 50.0127C49.7397 49.9867 49.8153 49.8125 49.9513 49.4901L50.2157 48.8583L50.5257 48.1484L50.7054 47.572L50.9388 46.9484L51.3468 45.9812C51.4469 45.6903 51.5323 45.4694 51.603 45.3185C51.6226 45.2252 51.6727 45.0797 51.7532 44.8821L52.047 44.1104L52.3048 43.5796L52.5986 42.8078L52.8107 42.3552L52.9396 42.0898L53.1811 41.4971L53.2496 41.3799L53.6282 40.5528C53.6282 40.5528 53.6662 40.4877 53.7423 40.3574C53.7423 40.3574 53.8032 40.2533 53.925 40.0449L53.9626 39.9358C53.9561 39.8272 53.9861 39.7311 54.0524 39.6476C54.1133 39.5434 54.1589 39.4652 54.1894 39.4131C54.2046 39.3871 54.2687 39.3372 54.3817 39.2634L54.4208 39.2863L54.5542 39.4167L54.6161 39.4004C54.7139 39.3527 54.7839 39.3675 54.8262 39.4446C54.8675 39.4338 54.8881 39.4284 54.8881 39.4284C54.9294 39.4175 54.9527 39.4224 54.9581 39.4431C54.9788 39.4377 54.9945 39.4556 55.0053 39.4969C55.0162 39.5381 55.0319 39.5561 55.0525 39.5506C55.0579 39.5713 55.0633 39.5919 55.0688 39.6125C55.0894 39.6071 55.1073 39.5914 55.1225 39.5654C55.2095 39.4764 55.2714 39.4602 55.3083 39.5166C55.3604 39.5471 55.3918 39.583 55.4026 39.6242C55.4287 39.6394 55.4471 39.6677 55.458 39.709C55.4634 39.7296 55.4791 39.7475 55.5051 39.7627C55.5106 39.7834 55.5236 39.791 55.5442 39.7856L55.5361 39.7546L55.4498 39.678L55.4727 39.6389C55.4987 39.6542 55.509 39.6515 55.5036 39.6308C55.5188 39.6048 55.5368 39.589 55.5574 39.5836L55.5965 39.6065L55.6909 39.714L55.699 39.745L55.7137 39.675C55.7083 39.6543 55.6953 39.6467 55.6746 39.6521C55.6225 39.6217 55.6139 39.5468 55.6487 39.4273C55.6433 39.4067 55.6509 39.3937 55.6716 39.3883C55.7129 39.3774 55.7411 39.359 55.7563 39.333L55.8639 39.2386L55.9258 39.2223C55.9887 39.2941 56.0256 39.3506 56.0364 39.3918C56.0527 39.4537 56.076 39.4586 56.1064 39.4065C56.1988 39.3382 56.2688 39.3529 56.3165 39.4507C56.3273 39.492 56.3431 39.5099 56.3637 39.5045C56.3691 39.5251 56.3979 39.5506 56.45 39.5811L56.5347 39.5258L56.6032 39.4086L56.6342 39.4005L56.8458 39.5765C56.8826 39.633 56.9347 39.6635 57.002 39.6679L57.033 39.6597C57.0634 39.6077 57.0868 39.6126 57.103 39.6745L57.1568 39.6273L57.2106 39.5801L57.2578 39.6339C57.3207 39.7056 57.3945 39.8186 57.479 39.9728L57.5034 40.0657C57.5663 40.1374 57.6032 40.1939 57.614 40.2352C57.6357 40.3177 57.6367 40.4057 57.617 40.499L57.6252 40.53L57.7764 40.8542L57.9408 40.9765C57.9668 40.9917 57.9749 41.0227 57.9651 41.0694C57.889 41.1996 57.8802 41.3343 57.9387 41.4733L57.924 41.5433C57.9034 41.5487 57.8855 41.5645 57.8702 41.5905C57.8757 41.6111 57.8914 41.6291 57.9174 41.6443L58.1453 41.8823C58.1453 41.8823 58.148 41.8926 58.1534 41.9132C58.1794 41.9285 58.1848 41.9491 58.1696 41.9751C58.2021 42.0989 58.2188 42.2048 58.2199 42.2928L58.1448 42.511L58.1199 43.0468C58.1155 43.1141 58.1138 43.1918 58.1148 43.2797C58.1104 43.347 58.1218 43.4323 58.1488 43.5355C58.139 43.5822 58.1395 43.6261 58.1503 43.6674C58.1764 43.6826 58.1921 43.7006 58.1975 43.7212L58.1909 43.8222C58.1605 43.8743 58.1453 43.9003 58.1453 43.9003L58.163 44.0941C58.1694 44.2027 58.1656 44.314 58.1513 44.428C58.1578 44.5366 58.1642 44.6452 58.1706 44.7538C58.1977 44.857 58.2095 44.9862 58.2061 45.1415C58.218 45.2707 58.2271 45.3896 58.2335 45.4982L58.2381 45.894L58.2868 46.0797C58.302 46.0537 58.333 46.0455 58.3797 46.0553C58.447 46.0597 58.4856 46.0386 58.4954 45.9919L58.5573 45.9757L58.5801 45.9366L58.5492 45.9447C58.5437 45.9241 58.5307 45.9165 58.5101 45.9219L58.541 45.9138L58.7039 45.9041C58.7919 45.9031 58.8565 45.8972 58.8978 45.8864C58.9543 45.8495 59.0031 45.8257 59.0444 45.8148L59.0672 45.7758C59.0466 45.7812 59.0363 45.7839 59.0363 45.7839C59.0309 45.7632 59.0282 45.7529 59.0282 45.7529L58.9663 45.7692L58.9353 45.7773L58.9663 45.7692C59.1205 45.6846 59.2492 45.6288 59.3524 45.6017C59.3524 45.6017 59.3627 45.599 59.3834 45.5936L59.3524 45.6017L59.2448 45.6961C59.2296 45.7221 59.2377 45.7531 59.2692 45.7889L59.3702 45.7955L59.4793 45.8331L59.5265 45.8869L59.6731 45.8153L59.7269 45.7681L59.7888 45.7519C59.7996 45.7932 59.7974 45.8268 59.7822 45.8529L59.7284 45.9001C59.6459 45.9217 59.6127 45.9635 59.629 46.0254L59.5361 46.0498C59.5415 46.0704 59.5236 46.0861 59.4823 46.097L59.5442 46.0807C59.6061 46.0645 59.6447 46.0433 59.6599 46.0173L59.7218 46.0011C59.7479 46.0163 59.7761 45.9978 59.8066 45.9457C59.8218 45.9197 59.8603 45.8986 59.9223 45.8823C59.907 45.9084 59.9124 45.929 59.9385 45.9442C59.9852 45.954 60.0085 45.9589 60.0085 45.9589C60.0704 45.9427 60.1144 45.9422 60.1404 45.9574L60.1942 45.9102C60.1888 45.8896 60.1758 45.882 60.1552 45.8874C60.1183 45.8309 60.1205 45.7972 60.1618 45.7864L60.2546 45.7621C60.3578 45.735 60.4273 45.7057 60.4632 45.6743L60.5332 45.689L60.4794 45.7362C60.4327 45.7264 60.3942 45.7475 60.3637 45.7996C60.3279 45.8311 60.292 45.8625 60.2561 45.894C60.2561 45.894 60.2257 45.9461 60.1648 46.0503C60.1496 46.0763 60.1447 46.0997 60.1501 46.1203C60.1707 46.1149 60.1837 46.1225 60.1892 46.1431L60.2739 46.0878C60.2685 46.0672 60.2658 46.0569 60.2658 46.0569C60.2864 46.0515 60.2967 46.0488 60.2967 46.0488C60.3695 46.0738 60.4493 46.0418 60.5362 45.9529L60.5981 45.9366L60.5444 45.9838L60.2592 46.1579L60.1663 46.1822C60.1251 46.193 60.0995 46.2218 60.0897 46.2685C60.0951 46.2891 60.1032 46.3201 60.1141 46.3613C60.1249 46.4026 60.1613 46.4151 60.2232 46.3989C60.2644 46.3881 60.2905 46.4033 60.3013 46.4445L60.3323 46.4364C60.3843 46.4669 60.4207 46.4794 60.4413 46.474C60.4109 46.5261 60.3854 46.5548 60.3647 46.5602C60.293 46.6232 60.2007 46.6915 60.0877 46.7652C60.0312 46.8021 59.9774 46.8493 59.9263 46.9068C59.8698 46.9437 59.8133 46.9806 59.7568 47.0174C59.6384 47.0705 59.4972 47.1627 59.3331 47.294C59.1691 47.4252 59.0409 47.525 58.9485 47.5934C58.8355 47.6671 58.7535 47.7327 58.7024 47.7902L58.6486 47.8374L58.7105 47.8212L59.0266 47.639L59.0885 47.6228L59.0657 47.6619L58.7658 47.9059C58.6474 47.959 58.6045 48.0475 58.6369 48.1713L58.5634 48.5214L58.5664 48.7853L58.7465 49.5982C58.7692 49.7687 58.7946 49.9495 58.8226 50.1406C58.8507 50.3318 58.8761 50.5126 58.8988 50.6831C58.9052 50.7917 58.9192 50.8872 58.9409 50.9698C58.9777 51.0263 59.0016 51.0751 59.0124 51.1164C59.0124 51.1164 59.0151 51.1267 59.0205 51.1474C59.026 51.168 59.0156 51.1707 58.9896 51.1555L58.9586 51.1636L58.952 51.2646C58.9899 51.409 59.0207 51.6105 59.0444 51.8689L59.0946 52.1866L59.1027 52.2175C59.0821 52.2229 59.0718 52.2256 59.0718 52.2256C59.0664 52.205 59.0637 52.1947 59.0637 52.1947L59.015 52.009C59.0095 51.9883 58.9965 51.9807 58.9759 51.9861L58.984 52.0171L58.9921 52.048C59.029 52.1045 59.0484 52.2207 59.0505 52.3966L59.1154 52.6443L59.2047 52.9847L59.3235 53.1852C59.3549 53.221 59.3815 53.2802 59.4031 53.3628C59.4052 53.5387 59.43 53.6755 59.4777 53.7733L59.4792 53.9052L59.4468 53.7814L59.4224 53.6885C59.4008 53.606 59.3742 53.5468 59.3427 53.511L59.3346 53.48C59.3346 53.48 59.3243 53.4827 59.3037 53.4881C59.3037 53.4881 59.3064 53.4984 59.3118 53.5191L59.3767 53.7667L59.4726 54.0062L59.4889 54.0681L59.5295 54.2229C59.5782 54.4086 59.6264 54.5503 59.6741 54.6481L59.7243 54.9657C59.7514 55.0689 59.8126 55.2183 59.908 55.4138L59.9633 55.4985C60.0415 55.5442 60.068 55.6034 60.043 55.6761C60.0234 55.7695 60.0266 55.8238 60.0526 55.839C60.1308 55.8847 60.1573 55.9439 60.1323 56.0166C60.1279 56.0839 60.1392 56.1692 60.1663 56.2724C60.1933 56.3755 60.2492 56.5043 60.3337 56.6585C60.3391 56.6791 60.3972 56.7742 60.5078 56.9437L60.6214 57.377C60.6529 57.4129 60.6822 57.4824 60.7092 57.5856L60.7336 57.6784C60.7857 57.7089 60.8117 57.7241 60.8117 57.7241L60.8655 57.6769L60.8574 57.646C60.878 57.6406 60.8856 57.6275 60.8802 57.6069L60.9502 57.6216C60.9502 57.6216 60.9763 57.6368 61.0284 57.6673L61.0593 57.6592C61.0648 57.6798 61.0571 57.6928 61.0365 57.6982L60.9127 57.7307L60.9208 57.7617C60.911 57.8083 60.9088 57.842 60.9142 57.8626C60.9457 57.8985 60.9538 57.9294 60.9386 57.9555C60.8821 57.9924 60.862 58.0418 60.8782 58.1037C60.9151 58.1602 60.9362 58.1987 60.9416 58.2194C60.9524 58.2606 60.9785 58.2759 61.0198 58.265L61.0817 58.2488L61.1517 58.2635C61.2126 58.1593 61.2479 58.0839 61.2577 58.0372C61.273 58.0111 61.2649 57.9802 61.2334 57.9443C61.2226 57.9031 61.2248 57.8694 61.24 57.8434L61.2319 57.8124L61.2628 57.8043L61.4288 58.0585L61.3618 58.3077L61.2314 58.4411C61.1955 58.4726 61.196 58.5165 61.2329 58.573C61.2698 58.6295 61.2654 58.6968 61.2197 58.775L61.0208 59.0257L60.967 59.0728C60.9105 59.1097 60.8567 59.1569 60.8056 59.2144C60.7752 59.2665 60.7523 59.3056 60.7371 59.3316L60.5758 59.4732ZM59.327 58.8744L59.3808 58.8272C59.422 58.8164 59.4454 58.8213 59.4508 58.842L59.4589 58.8729L59.6741 58.6842L59.666 58.6532L59.6269 58.6304C59.591 58.6618 59.5421 58.6857 59.4802 58.7019C59.4183 58.7181 59.3613 58.711 59.3092 58.6806L59.2702 58.6578C59.2549 58.6838 59.237 58.6995 59.2164 58.705C59.1957 58.7104 59.1881 58.7234 59.1935 58.744L59.2732 58.9216L59.327 58.8744ZM59.6893 57.9854C59.7099 57.98 59.7175 57.967 59.7121 57.9464C59.7328 57.9409 59.717 57.923 59.6649 57.8926L59.6502 57.9626L59.6893 57.9854ZM60.8127 58.4847C60.7867 58.4695 60.771 58.4516 60.7655 58.431C60.7862 58.4255 60.7938 58.4125 60.7884 58.3919L60.7412 58.3381L60.6564 58.3934L60.6955 58.4162L60.7899 58.5238L60.8209 58.5157L60.8127 58.4847ZM59.4325 57.2588C59.4532 57.2534 59.4608 57.2404 59.4554 57.2197L59.4391 57.1578L59.3919 57.104C59.3919 57.104 59.3816 57.1067 59.361 57.1121C59.361 57.1121 59.3637 57.1225 59.3691 57.1431L59.3854 57.205C59.406 57.1996 59.419 57.2072 59.4244 57.2278L59.4325 57.2588ZM59.226 56.8498C59.2456 56.7564 59.25 56.6891 59.2392 56.6479C59.2392 56.6479 59.2365 56.6375 59.2311 56.6169C59.2311 56.6169 59.2208 56.6196 59.2001 56.625C59.2001 56.625 59.1822 56.6407 59.1464 56.6722C59.1311 56.6983 59.1365 56.7189 59.1626 56.7341L59.1951 56.8579L59.226 56.8498ZM61.5784 58.2508C61.5991 58.2454 61.6067 58.2324 61.6013 58.2117C61.6622 58.1076 61.6926 58.0555 61.6926 58.0555C61.6872 58.0348 61.6845 58.0245 61.6845 58.0245C61.7051 58.0191 61.7154 58.0164 61.7154 58.0164L61.8164 58.023C61.7708 58.1011 61.7479 58.1402 61.7479 58.1402C61.7175 58.1923 61.6713 58.2265 61.6094 58.2427L61.5784 58.2508ZM59.1692 56.6331C59.1996 56.581 59.2149 56.555 59.2149 56.555L59.1448 56.5403C59.1448 56.5403 59.1345 56.543 59.1139 56.5484C59.1139 56.5484 59.1166 56.5587 59.122 56.5794L59.1692 56.6331ZM58.6399 56.5073C58.6812 56.4965 58.6964 56.4704 58.6856 56.4292C58.6487 56.3727 58.6168 56.2928 58.5897 56.1896C58.5735 56.1277 58.5339 56.0609 58.471 55.9892C58.4602 55.9479 58.4623 55.9143 58.4776 55.8882C58.4776 55.8882 58.4749 55.8779 58.4695 55.8573C58.464 55.8366 58.4483 55.8187 58.4223 55.8035L58.3913 55.8116L58.4075 55.8735C58.4617 56.0799 58.5099 56.2216 58.5522 56.2987C58.5576 56.3194 58.55 56.3324 58.5293 56.3378C58.5554 56.353 58.5765 56.3916 58.5928 56.4535C58.6036 56.4948 58.6193 56.5127 58.6399 56.5073ZM52.6087 52.4321C52.6087 52.4321 52.5984 52.4348 52.5778 52.4403C52.5778 52.4403 52.575 52.4299 52.5696 52.4093L52.5925 52.3702L52.6234 52.3621L52.7391 52.2987L52.6087 52.4321ZM59.0571 56.3317C59.0777 56.3263 59.0853 56.3133 59.0799 56.2927C59.0745 56.272 59.0587 56.2541 59.0327 56.2389C59.0327 56.2389 59.03 56.2286 59.0246 56.2079C59.0192 56.1873 59.0268 56.1743 59.0474 56.1688C59.0887 56.158 59.0833 56.1374 59.0312 56.1069L59.0231 56.076C59.0687 55.9978 59.0579 55.9566 58.9906 55.9522L58.9825 55.9212L58.9972 55.8512L58.919 55.8055L58.8652 55.8527C58.9194 56.0591 58.9703 56.2111 59.018 56.3089C59.0234 56.3295 59.0261 56.3398 59.0261 56.3398C59.0467 56.3344 59.0571 56.3317 59.0571 56.3317ZM58.3573 55.5559L58.3492 55.5249L58.333 55.463L58.2858 55.4092L58.2939 55.4402L58.2954 55.5721L58.3426 55.6259L58.3573 55.5559ZM52.9801 52.3347L52.972 52.3038C52.9927 52.2983 53.0209 52.2799 53.0568 52.2484C53.1078 52.1909 53.1567 52.1671 53.2034 52.1769L53.2344 52.1688L53.1806 52.216C53.1089 52.2789 53.0524 52.3158 53.0111 52.3266L52.9801 52.3347ZM58.9109 55.7746L58.9175 55.6736C58.834 55.6073 58.7993 55.5171 58.8135 55.4031C58.8135 55.4031 58.8032 55.4058 58.7825 55.4113C58.7825 55.4113 58.7798 55.4009 58.7744 55.3803C58.744 55.4324 58.7315 55.4688 58.7369 55.4894L58.8247 55.698L58.7937 55.7061L58.88 55.7827L58.9109 55.7746ZM58.2533 55.2854C58.2479 55.2648 58.2501 55.2311 58.2599 55.1844C58.2697 55.1378 58.2486 55.0992 58.1965 55.0687L58.1883 55.0378C58.209 55.0324 58.2193 55.0297 58.2193 55.0297C58.2139 55.009 58.2112 54.9987 58.2112 54.9987C58.221 54.952 58.2151 54.8874 58.1934 54.8049L58.1853 54.7739L58.1543 54.782L58.1396 54.8521C58.1505 54.8933 58.1456 54.9167 58.1249 54.9221C58.0792 55.0002 58.0982 55.0725 58.1817 55.1388L58.1899 55.1697L58.2061 55.2316L58.2142 55.2626L58.2223 55.2935L58.2533 55.2854ZM52.6077 51.6715C52.6696 51.6553 52.7082 51.6341 52.7234 51.6081L52.7315 51.639L52.7853 51.5918C52.7799 51.5712 52.7669 51.5636 52.7462 51.569L52.7153 51.5771L52.6077 51.6715ZM59.3803 55.4199L59.3021 55.3742L59.2955 55.4752L59.3037 55.5061L59.3803 55.4199ZM59.3316 55.2342C59.3109 55.2396 59.3006 55.2423 59.3006 55.2423C59.2952 55.2217 59.2925 55.2113 59.2925 55.2113C59.2621 55.2634 59.2365 55.2922 59.2159 55.2976L59.2631 55.3514L59.3316 55.2342ZM53.277 51.8268L53.4074 51.6933L53.4383 51.6852L53.4465 51.7162L53.277 51.8268ZM57.9935 54.2949L57.9463 54.2411L57.9316 54.3112L57.9869 54.3959L57.9935 54.2949ZM58.7272 55.3265C58.7577 55.2744 58.7702 55.2381 58.7648 55.2174C58.7171 55.1197 58.6635 54.9573 58.6039 54.7303L58.5567 54.6765C58.5459 54.6352 58.5405 54.6146 58.5405 54.6146L58.4431 54.2432L58.3457 53.8717C58.3348 53.8305 58.2985 53.8179 58.2366 53.8342L58.2218 53.9042L58.2543 54.028L58.3421 54.2366C58.3475 54.2572 58.3507 54.3115 58.3517 54.3994C58.368 54.4614 58.4021 54.5075 58.4542 54.538L58.4624 54.5689C58.4471 54.595 58.4449 54.6286 58.4558 54.6699L58.6166 55.157L58.6491 55.2808L58.7272 55.3265ZM59.2032 54.8708L59.156 54.8171C59.1256 54.8692 59.1103 54.8952 59.1103 54.8952C59.1103 54.8952 59.1364 54.9104 59.1885 54.9409L59.2032 54.8708ZM57.9448 54.1092L57.9367 54.0782L57.8504 54.0016L57.8748 54.0945L57.8829 54.1254L57.9301 54.1792L57.9448 54.1092ZM57.7251 53.9022L57.6779 53.8484C57.6887 53.8897 57.6838 53.913 57.6632 53.9184L57.7104 53.9722L57.7251 53.9022ZM53.4353 51.4213L53.5348 51.296L53.3881 51.3676L53.4044 51.4295L53.4353 51.4213ZM57.8408 53.8387C57.8191 53.7562 57.7926 53.697 57.7611 53.6611L57.7301 53.6693L57.7789 53.855L57.8489 53.8697L57.8408 53.8387ZM59.0246 54.1899L59.0083 54.128C59.0083 54.128 58.9904 54.1437 58.9546 54.1752C58.9339 54.1806 58.9182 54.1627 58.9074 54.1214L58.9155 54.1523L58.9317 54.2142L59.0018 54.229L59.0246 54.1899ZM57.7423 52.7067L57.6561 52.6301L57.6104 52.7082C57.631 52.7028 57.6674 52.7153 57.7195 52.7457L57.7423 52.7067ZM58.5745 52.8523L58.5958 52.6813C58.5904 52.6607 58.5774 52.6531 58.5567 52.6585C58.5567 52.6585 58.5464 52.6612 58.5258 52.6666C58.5258 52.6666 58.5285 52.6769 58.5339 52.6975L58.5583 52.7904L58.5745 52.8523L58.5826 52.8833L58.5745 52.8523ZM58.2594 53.7951C58.254 53.7745 58.2513 53.7642 58.2513 53.7642C58.2719 53.7587 58.2822 53.756 58.2822 53.756L58.2482 53.5003L58.094 52.9122L58.0209 52.6336L57.9641 52.4169L57.8829 52.1074L57.8261 51.8907C57.8359 51.8441 57.8299 51.7794 57.8083 51.6969L57.7839 51.604C57.7731 51.5628 57.7753 51.5291 57.7905 51.5031C57.7797 51.4618 57.7586 51.4232 57.7271 51.3874C57.7109 51.3255 57.7077 51.2712 57.7175 51.2245C57.7273 51.1778 57.7165 51.1365 57.685 51.1007C57.6688 51.0388 57.6682 50.9948 57.6835 50.9687L57.6754 50.9378L57.6444 50.9459C57.639 50.9253 57.6466 50.9122 57.6672 50.9068L57.6591 50.8759C57.6473 50.7467 57.6089 50.5582 57.5439 50.3106C57.5385 50.29 57.5201 50.2617 57.4886 50.2259C57.4778 50.1846 57.4746 50.1303 57.479 50.063C57.4942 50.0369 57.4861 50.006 57.4546 49.9701C57.4438 49.9289 57.4357 49.8979 57.4303 49.8773L57.3491 49.5677L57.3328 49.5058L57.3491 49.5677L57.4511 50.335C57.4835 50.4588 57.5116 50.6499 57.5353 50.9084L57.5921 51.125L57.7139 51.5893C57.6987 51.6154 57.7068 51.6463 57.7383 51.6822C57.7643 51.6974 57.7724 51.7284 57.7626 51.775C57.7474 51.8011 57.7479 51.8451 57.7641 51.907C57.7479 51.8451 57.7268 51.8065 57.7007 51.7913L57.7428 52.078L57.8159 52.3566C57.8321 52.4185 57.8354 52.4728 57.8255 52.5194C57.8418 52.5813 57.8607 52.6536 57.8824 52.7361C57.9247 52.8132 57.9409 52.8751 57.9311 52.9218L57.9702 52.9447L58.0432 53.2232L58.1082 53.4709C58.1407 53.5947 58.1753 53.6848 58.2122 53.7413L58.2594 53.7951ZM55.2849 50.2746C55.3468 50.2583 55.375 50.2399 55.3696 50.2193L55.4544 50.164L55.4234 50.1721L55.3615 50.1883C55.3311 50.2404 55.3055 50.2692 55.2849 50.2746ZM57.3932 51.3757L57.4161 51.3366C57.3998 51.2747 57.3814 51.2465 57.3607 51.2519L57.3136 51.1981L57.2988 51.2681L57.3623 51.3838L57.3932 51.3757ZM57.3283 51.1281C57.3381 51.0814 57.3295 51.0065 57.3024 50.9033L57.2552 50.8495C57.266 50.8908 57.2611 50.9141 57.2405 50.9195C57.2621 51.0021 57.2681 51.0667 57.2582 51.1134L57.2745 51.1753L57.3364 51.159L57.3283 51.1281ZM57.172 51.0367C57.1612 50.9955 57.1449 50.9336 57.1233 50.851C57.1223 50.7631 57.15 50.7006 57.2065 50.6638C57.2271 50.6584 57.2374 50.6557 57.2374 50.6557C57.232 50.635 57.2293 50.6247 57.2293 50.6247L57.1903 50.6019L57.1284 50.6181C57.1175 50.5768 57.1197 50.5432 57.1349 50.5171L57.1268 50.4862C57.1322 50.5068 57.1349 50.5171 57.1349 50.5171C57.1556 50.5117 57.1659 50.509 57.1659 50.509L57.174 50.54L57.1659 50.509L57.1791 50.3071C57.1737 50.2864 57.1607 50.2788 57.14 50.2842L57.0472 50.3086C57.0526 50.3292 57.045 50.3422 57.0243 50.3477L57.0553 50.3395C57.102 50.3493 57.1101 50.3803 57.0796 50.4324C57.0796 50.4324 57.072 50.4454 57.0568 50.4715C57.0362 50.4769 57.0286 50.4899 57.034 50.5105L57.102 51.022L57.1426 51.1768L57.1507 51.2077L57.172 51.0367ZM57.3613 50.6232L57.2963 50.3756L57.2572 50.3527L57.2654 50.3837L57.3059 50.5384C57.3114 50.5591 57.3065 50.5824 57.2912 50.6085C57.2912 50.6085 57.3043 50.6161 57.3303 50.6313C57.3303 50.6313 57.333 50.6416 57.3384 50.6623C57.3384 50.6623 57.3487 50.6595 57.3694 50.6541L57.3613 50.6232ZM59.2073 51.8593C59.1964 51.818 59.1753 51.7794 59.1438 51.7436C59.1276 51.6817 59.119 51.6068 59.118 51.5188C59.0963 51.4363 59.0845 51.307 59.0824 51.1311L59.1134 51.123C59.0894 51.2837 59.118 51.5188 59.1991 51.8283L59.2073 51.8593ZM57.1385 50.1523L57.0964 49.8656L57.0573 49.8428L57.0736 49.9047L57.0441 50.0447L57.0456 50.1766L57.1238 50.2223L57.1385 50.1523ZM58.3908 50.3862L58.4218 50.3781C58.4011 50.3835 58.3908 50.3862 58.3908 50.3862C58.3854 50.3656 58.3827 50.3553 58.3827 50.3553L58.3908 50.3862L58.4248 50.642L58.4558 50.6338L58.3908 50.3862ZM58.0727 51.0652L58.0453 50.7084C58.0639 50.5271 58.0781 50.4131 58.0879 50.3664C58.0662 50.2839 58.0733 50.2269 58.1092 50.1954C58.119 50.1487 58.1131 50.0841 58.0914 50.0016C58.0644 49.8984 58.0498 49.7589 58.0478 49.583L58.0316 49.5211C58.0316 49.5211 58.0419 49.5184 58.0625 49.5129C58.0571 49.4923 58.0414 49.4744 58.0153 49.4592C58.0099 49.4385 58.0148 49.4152 58.0301 49.3891L57.9717 49.0405L57.9458 48.8157C57.9404 48.7951 57.9274 48.7875 57.9067 48.7929L57.8758 48.801L57.892 48.8629L57.9504 49.2115C57.9774 49.3147 57.9861 49.3896 57.9763 49.4363C57.9999 49.6948 58.0074 49.8913 57.9986 50.0259L58.0016 50.2898L57.9316 50.2751L57.9169 50.3451C57.9494 50.4689 57.9634 50.5645 57.959 50.6318L57.9915 50.7556C57.9827 50.8903 57.9891 50.9989 58.0108 51.0814L58.058 51.1352L58.0727 51.0652ZM57.5759 49.0451C57.5705 49.0245 57.5678 49.0141 57.5678 49.0141C57.5884 49.0087 57.5987 49.006 57.5987 49.006C57.5825 48.9441 57.5793 48.8898 57.5891 48.8431C57.5891 48.8431 57.5788 48.8458 57.5581 48.8513C57.5581 48.8513 57.5554 48.8409 57.55 48.8203L57.5581 48.8513C57.5483 48.8979 57.5516 48.9522 57.5678 49.0141L57.5759 49.0451ZM53.6916 48.7406L54.0762 48.4412L54.8145 47.8506L55.5153 47.3691C55.6282 47.2953 55.6739 47.2172 55.6523 47.1346L55.5878 46.2583L55.4904 45.8869L55.4173 45.6083C55.4119 45.5877 55.4195 45.5746 55.4402 45.5692L55.432 45.5383L55.3067 45.4388L55.1991 45.5332C55.1991 45.5332 55.1839 45.5592 55.1535 45.6113L54.9201 46.235L54.5938 46.8829L54.0554 47.9835L53.6525 48.7178C53.6525 48.7178 53.6552 48.7281 53.6606 48.7487C53.6606 48.7487 53.6503 48.7514 53.6297 48.7569L53.6916 48.7406ZM58.5979 48.1485L58.5426 48.0637L58.4888 48.1109C58.479 48.1576 58.4822 48.2119 58.4984 48.2738L58.5684 48.2885L58.5979 48.1485ZM58.675 47.4335L59.1053 47.056C59.1259 47.0506 59.1335 47.0376 59.1281 47.0169L59.0662 47.0332L58.7973 47.2691L58.5202 47.4741C58.5202 47.4741 58.5229 47.4844 58.5284 47.5051C58.5284 47.5051 58.518 47.5078 58.4974 47.5132L58.5284 47.5051L58.675 47.4335ZM59.1231 47.2498C59.185 47.2336 59.2518 47.194 59.3235 47.1311L59.3544 47.123L59.3154 47.1001L59.1231 47.2498L59.0921 47.2579L59.1231 47.2498ZM59.4671 46.7957L59.4899 46.7566L59.459 46.7647L59.2667 46.9144L59.2357 46.9225C59.2563 46.9171 59.2694 46.9247 59.2748 46.9454L59.4671 46.7957ZM57.0233 45.551C57.044 45.5455 57.0516 45.5325 57.0462 45.5119L57.0837 45.4028L57.0675 45.3409L57.0137 45.3881L57.0152 45.52L57.0233 45.551ZM59.2814 46.8444C59.3379 46.8075 59.3917 46.7603 59.4427 46.7028C59.4938 46.6453 59.5476 46.5981 59.6041 46.5613C59.6247 46.5558 59.635 46.5531 59.635 46.5531C59.6296 46.5325 59.6269 46.5222 59.6269 46.5222C59.6215 46.5015 59.6085 46.4939 59.5879 46.4993L59.4803 46.5937L59.0713 46.8002L59.0566 46.8703L59.1038 46.9241L59.1657 46.9078L59.2814 46.8444ZM57.3029 46.2385C57.329 46.2537 57.3599 46.2456 57.3958 46.2142C57.4523 46.1773 57.4778 46.1485 57.4724 46.1279C57.4822 46.0812 57.4763 46.0166 57.4546 45.9341L57.4856 45.9259L57.4952 46.0888L57.5505 46.1736L57.6272 46.0873C57.5947 45.9635 57.572 45.793 57.5592 45.5758C57.5538 45.5552 57.5407 45.5476 57.5201 45.553C57.5147 45.5324 57.5044 45.5351 57.4892 45.5611C57.4946 45.5817 57.487 45.5948 57.4663 45.6002L57.4582 45.5692L57.4064 45.1196L57.3938 44.6929L57.3856 44.6619L57.3613 44.5691L57.3303 44.5772C57.3303 44.5772 57.32 44.5799 57.2994 44.5853C57.2994 44.5853 57.3021 44.5956 57.3075 44.6163L57.2994 44.5853L57.2588 44.4306L57.2278 44.4387L57.2324 44.8345C57.229 44.9897 57.2392 45.1966 57.2628 45.4551C57.2723 45.8275 57.2803 46.068 57.2867 46.1766C57.2715 46.2027 57.2666 46.226 57.272 46.2466C57.2926 46.2412 57.3029 46.2385 57.3029 46.2385ZM58.0707 45.5078L58.0235 45.454C58.0126 45.4128 57.9915 45.3742 57.96 45.3384C57.9232 45.2819 57.92 45.2276 57.9504 45.1755L57.9423 45.1445L57.8804 45.1608C57.8543 45.1455 57.8337 45.1509 57.8185 45.177C57.7978 45.1824 57.7902 45.1954 57.7956 45.2161C57.7858 45.2627 57.7945 45.3377 57.8215 45.4408L57.8687 45.4946C57.8687 45.4946 57.8844 45.5126 57.9159 45.5484C57.9419 45.5636 57.9626 45.5582 57.9778 45.5322C57.9984 45.5268 58.0115 45.5344 58.0169 45.555L58.0641 45.6088L58.0707 45.5078ZM60.2815 46.7475C60.2761 46.7268 60.2734 46.7165 60.2734 46.7165C60.294 46.7111 60.3043 46.7084 60.3043 46.7084L60.3353 46.7003L60.4657 46.5668L60.5504 46.5115L60.6205 46.5262C60.6205 46.5262 60.6052 46.5523 60.5748 46.6044C60.5129 46.6206 60.4254 46.6656 60.3125 46.7394L60.2815 46.7475ZM57.9702 44.8725L57.9068 44.7568L57.8692 44.8659C57.8953 44.8812 57.9137 44.9094 57.9245 44.9507L57.9702 44.8725ZM60.86 46.4303L60.8828 46.3913L60.9432 46.2431L60.9741 46.235L61.0132 46.2578L60.8909 46.4222L60.86 46.4303ZM56.9386 43.5882L56.8833 43.5035C56.8681 43.5295 56.8659 43.5632 56.8767 43.6045L56.9239 43.6583L56.9386 43.5882ZM59.9862 45.3693L60.04 45.3221L60.11 45.3368L60.0562 45.384L59.9862 45.3693ZM58.2879 42.8043C58.2966 42.6696 58.3081 42.5453 58.3224 42.4313C58.3312 42.2967 58.3427 42.1724 58.3569 42.0584L58.401 41.8483L58.432 41.8402L58.4401 41.8711C58.4225 42.1404 58.3794 42.4384 58.3107 42.7652L58.296 42.8352L58.2879 42.8043ZM57.1203 40.497C57.104 40.4351 57.0856 40.4068 57.065 40.4123L57.0178 40.3585L57.034 40.4204L57.0812 40.4742L57.0974 40.5361L57.1203 40.497ZM58.2128 41.0044L58.1965 40.9425L58.296 40.8172C58.3166 40.8118 58.3296 40.8194 58.335 40.84L58.2437 40.9963L58.2128 41.0044ZM62.4237 56.0442C62.2783 55.9941 62.167 55.9902 62.0899 56.0325C62.0334 56.0694 61.9818 56.0829 61.9351 56.0731C61.8938 56.0839 61.8526 56.0947 61.8113 56.1056C61.6875 56.138 61.5968 56.1287 61.5393 56.0776C61.5187 56.0831 61.4926 56.0678 61.4612 56.032C61.4145 56.0222 61.3732 56.033 61.3373 56.0645C61.2853 56.034 61.2228 56.0063 61.1501 55.9812C61.0622 55.9822 61.0024 55.9648 60.971 55.929C60.9656 55.9083 60.9629 55.898 60.9629 55.898C60.9422 55.9034 60.9319 55.9061 60.9319 55.9061C60.8027 55.918 60.6675 55.8652 60.5265 55.7478L60.2758 55.5489L59.9942 55.3581L59.9617 55.2343C59.9878 55.2495 60.0084 55.2441 60.0236 55.2181C60.0236 55.2181 60.0263 55.2284 60.0317 55.249L60.3037 55.2769L60.3347 55.2688C60.3347 55.2688 60.332 55.2585 60.3266 55.2378C60.3266 55.2378 60.3162 55.2406 60.2956 55.246L59.9764 55.1643L59.9683 55.1333C60.0096 55.1225 60.0275 55.1068 60.0221 55.0861C60.0167 55.0655 60.0037 55.0579 59.983 55.0633C59.9309 55.0328 59.9201 54.9916 59.9506 54.9395C59.9604 54.8928 59.9626 54.8591 59.9572 54.8385L59.98 54.7994C60.0006 54.794 60.0316 54.7859 60.0729 54.7751C60.1141 54.7643 60.1505 54.7768 60.1819 54.8126C60.1874 54.8333 60.2004 54.8409 60.221 54.8355L60.2129 54.8045C60.1608 54.7741 60.1244 54.7615 60.1038 54.767C60.0832 54.7724 60.0625 54.7778 60.0419 54.7832C60.0159 54.768 60.0077 54.737 60.0175 54.6903L60.0094 54.6594C59.9627 54.6496 59.9313 54.6137 59.915 54.5518C59.8988 54.4899 59.8983 54.4459 59.9135 54.4199C59.9548 54.4091 59.9727 54.3933 59.9673 54.3727C59.9565 54.3314 59.9457 54.2901 59.9348 54.2489C59.898 54.1924 59.8844 54.1408 59.8942 54.0941L59.8719 53.5045C59.8665 53.4838 59.8829 53.3362 59.9211 53.0615L59.946 52.5257L60.0475 51.9036L60.1703 51.1105L60.2733 50.6203C60.2777 50.553 60.2821 50.4856 60.2865 50.4183C60.2855 50.3304 60.2948 50.2397 60.3144 50.1463L60.3748 49.9982L60.4844 49.407L60.5351 49.096C60.5125 48.9255 60.5284 48.7338 60.5828 48.5211C60.6167 48.3137 60.6407 48.153 60.6549 48.039L60.699 47.8289C60.7275 47.6009 60.7591 47.4272 60.7939 47.3078C60.8267 47.0125 60.8704 46.7584 60.9249 46.5457C60.9597 46.4262 60.9712 46.3019 60.9594 46.1727C60.9465 45.9555 60.9624 45.7639 61.0071 45.5978C61.0473 45.499 61.0795 45.3693 61.1035 45.2086C61.1275 45.0479 61.1493 44.9209 61.1689 44.8275L61.2491 44.3764C61.2775 44.1484 61.3092 43.9747 61.344 43.8553C61.3832 43.6686 61.423 43.5258 61.4632 43.427L61.4551 43.3961L61.5287 43.0459L61.5957 42.7968C61.5947 42.7088 61.6192 42.5921 61.6693 42.4467C61.6889 42.3533 61.6982 42.2626 61.6972 42.1747C61.7168 42.0813 61.744 41.9749 61.7789 41.8555C61.8486 41.6167 61.8905 41.4403 61.9047 41.3263C62.0529 40.714 62.1537 40.2575 62.2071 39.9567C62.3161 39.5312 62.3847 39.2044 62.4132 38.9764C62.4829 38.7376 62.5221 38.5508 62.5309 38.4162C62.5799 38.1828 62.5801 37.9732 62.5314 37.7875C62.5152 37.7256 62.5114 37.6273 62.5202 37.4927C62.5138 37.3841 62.5563 37.2517 62.6476 37.0954L62.8288 36.6509C62.869 36.5521 62.9554 36.4191 63.0881 36.252C63.1642 36.1218 63.3516 35.9954 63.6503 35.873C63.8154 35.8297 63.9419 35.8075 64.0298 35.8065C64.0765 35.8163 64.1205 35.8158 64.1618 35.805C64.2183 35.7681 64.2698 35.7546 64.3165 35.7644C64.7194 35.7028 65.0511 35.7482 65.3116 35.9004L65.6323 36.114L65.7805 36.1744L65.8276 36.2282C65.8124 36.2542 65.8248 36.4274 65.8647 36.7478L65.8824 36.9416L65.8921 37.1045C65.9246 37.2283 66.0364 37.2762 66.2275 37.2481C66.31 37.2265 66.3773 37.2309 66.4294 37.2613L66.4376 37.2923L66.4066 37.3004L66.2209 37.3491C66.1492 37.412 66.1084 37.4668 66.0986 37.5135L65.9712 37.9108C65.9712 37.9108 65.9739 37.9211 65.9794 37.9418C65.9794 37.9418 65.969 37.9445 65.9484 37.9499C65.8615 38.0389 65.8549 38.1398 65.9286 38.2528L65.922 38.3538C65.9274 38.3744 65.9149 38.4108 65.8845 38.4629C65.9007 38.5248 65.8985 38.5585 65.8779 38.5639C65.8626 38.5899 65.842 38.5953 65.816 38.5801C65.7899 38.5649 65.7666 38.56 65.7459 38.5654C65.684 38.5816 65.6379 38.6158 65.6074 38.6679L65.4425 39.1743C65.3728 39.4131 65.3439 39.5972 65.3557 39.7264C65.4098 39.9327 65.3792 40.1944 65.2639 40.5114L65.071 41.2898L64.929 41.7571L64.8914 41.8662C64.8968 41.8868 64.8897 41.9438 64.8701 42.0372C64.8603 42.0839 64.8456 42.1539 64.826 42.2473C64.8009 42.32 64.7786 42.4031 64.759 42.4964C64.7306 42.7244 64.6989 42.8981 64.6641 43.0175C64.6292 43.137 64.5998 43.277 64.5758 43.4377C64.5724 43.593 64.5712 43.7146 64.5722 43.8025L64.5245 44.3774L64.5555 44.3693L64.6534 44.1121C64.7742 43.8157 64.8346 43.6676 64.8346 43.6676C64.9564 43.4592 65.2079 43.2829 65.5891 43.1388C65.7542 43.0955 65.8753 43.0527 65.9524 43.0104L65.9834 43.0023L66.0844 43.0089C66.0691 43.035 66.0409 43.0534 65.9996 43.0642L65.5287 43.287C65.2507 43.404 65.0534 43.5771 64.9371 43.8061C64.8457 43.9624 64.7908 44.1312 64.7722 44.3125C64.7295 44.6545 64.6446 44.9194 64.5174 45.1071C64.5174 45.1071 64.4337 45.2504 64.2663 45.5369C64.1749 45.6932 64.0895 45.9141 64.01 46.1996C63.9403 46.4384 63.9011 46.6252 63.8923 46.7598C63.8138 47.1333 63.7652 47.4107 63.7466 47.592C63.727 47.6853 63.6998 47.7917 63.6649 47.9111C63.6453 48.0045 63.6208 48.1212 63.5914 48.2613C63.5663 48.334 63.5467 48.4274 63.5325 48.5414C63.5183 48.6554 63.496 48.7384 63.4655 48.7905C63.4155 48.936 63.3664 49.1694 63.3184 49.4908C63.3184 49.4908 63.3031 49.5168 63.2727 49.5689C63.2835 49.6102 63.2737 49.6569 63.2433 49.709L63.194 50.1519L63.1382 50.6959L63.086 50.875L63.0565 51.0151C63.0674 51.0563 63.0858 51.0846 63.1118 51.0998C63.1064 51.0792 63.114 51.0661 63.1347 51.0607C63.1553 51.0553 63.1629 51.0423 63.1575 51.0217L63.293 50.6553C63.293 50.6553 63.3082 50.6293 63.3387 50.5772L63.363 50.67L63.1996 51.3084L63.0834 52.0005C63.079 52.0678 63.0926 52.1194 63.124 52.1553C63.1501 52.1705 63.1913 52.1597 63.2478 52.1228C63.3097 52.1065 63.3689 52.08 63.4254 52.0431C63.4819 52.0062 63.5411 51.9797 63.603 51.9634C63.7008 51.9157 63.8165 51.8523 63.9501 51.7732C64.0783 51.6734 64.1913 51.5996 64.2891 51.5519L64.558 51.316L64.6803 51.1516L64.7341 51.1044C64.8579 51.0719 64.922 51.022 64.9264 50.9547C64.921 50.9341 64.9183 50.9237 64.9183 50.9237C64.9389 50.9183 64.9492 50.9156 64.9492 50.9156L64.9573 50.9466L64.8741 51.1338C64.8437 51.1859 64.8491 51.2065 64.8904 51.1957C64.911 51.1903 64.9267 51.2082 64.9376 51.2495C64.9636 51.2647 64.9842 51.2593 64.9995 51.2333L65.3075 51.0202L65.3384 51.012C65.3591 51.0066 65.3797 51.0012 65.4003 50.9958C65.4155 50.9697 65.4074 50.9388 65.376 50.9029L65.3907 50.8329L65.4445 50.7857C65.5064 50.7695 65.5297 50.7744 65.5145 50.8004L65.5536 50.8233L65.5764 50.7842C65.5449 50.7483 65.5575 50.712 65.614 50.6751L65.8372 50.5173L65.961 50.4848C65.961 50.4848 65.9741 50.4924 66.0001 50.5077C66.0414 50.4968 66.0566 50.4708 66.0458 50.4295L66.0686 50.3904C66.0947 50.4057 66.1283 50.4079 66.1696 50.397C66.2054 50.3656 66.2364 50.3575 66.2624 50.3727L66.3162 50.3255C66.3619 50.2473 66.3847 50.2083 66.3847 50.2083C66.4 50.1822 66.4179 50.1665 66.4385 50.1611C66.4798 50.1503 66.508 50.1318 66.5233 50.1058C66.5699 50.1156 66.6085 50.0944 66.639 50.0423C66.6694 49.9903 66.6949 49.9615 66.7156 49.9561C66.7568 49.9453 66.7927 49.9138 66.8232 49.8617L66.9632 49.8911L66.9404 49.9302C66.873 49.9258 66.8323 49.9806 66.8181 50.0946C66.7974 50.1 66.7898 50.113 66.7952 50.1337C66.8159 50.1283 66.8262 50.1256 66.8262 50.1256L66.8881 50.1093C66.9131 50.0366 66.949 50.0051 66.9957 50.0149L67.0495 49.9678C67.0647 49.9417 67.0799 49.9157 67.0951 49.8896C67.131 49.8582 67.1772 49.824 67.2337 49.7871C67.2543 49.7817 67.2673 49.7893 67.2727 49.8099L67.3118 49.8328C67.327 49.8067 67.358 49.7986 67.4047 49.8084C67.4459 49.7976 67.4715 49.7688 67.4813 49.7222L67.5351 49.675C67.6741 49.6165 67.8001 49.5503 67.9131 49.4766C68.0261 49.4028 68.1211 49.3448 68.1983 49.3025L68.3678 49.1919C68.383 49.1659 68.4036 49.1604 68.4297 49.1757C68.4709 49.1648 68.5073 49.1774 68.5388 49.2132L68.586 49.267L68.625 49.2898L68.6184 49.3908L68.3429 49.7278L68.2825 49.8759C68.2727 49.9226 68.2884 49.9405 68.3297 49.9297L68.3688 49.9525C68.3688 49.9525 68.3715 49.9629 68.3769 49.9835C68.3769 49.9835 68.3666 49.9862 68.3459 49.9916L68.0851 50.2585C67.9417 50.3844 67.8368 50.4891 67.7705 50.5726C67.714 50.6095 67.6553 50.68 67.5944 50.7842L67.6026 50.8152L67.6335 50.807L67.8796 50.6102L67.9106 50.602C67.8747 50.6335 67.8388 50.665 67.803 50.6964C67.7671 50.7279 67.734 50.7697 67.7035 50.8218C67.7035 50.8218 67.6731 50.8739 67.6122 50.978L67.5437 51.0953L67.4361 51.1896L67.4524 51.2515L67.5143 51.2353L67.7375 51.0775L67.9999 50.9425C68.1846 50.8059 68.3361 50.711 68.4545 50.6579C68.4653 50.6991 68.4631 50.7328 68.4479 50.7588C68.4479 50.7588 68.4376 50.7615 68.417 50.767C68.4116 50.7463 68.4116 50.7463 68.417 50.767L68.386 50.7751C68.4381 50.8055 68.4332 50.8289 68.3713 50.8451L68.3403 50.8532L68.2556 50.9085L68.3109 50.9933C68.3163 51.0139 68.319 51.0242 68.319 51.0242C68.3397 51.0188 68.35 51.0161 68.35 51.0161L68.728 50.8177L68.759 50.8096L68.8128 50.7624L68.798 50.8324L68.8143 50.8943L69.0081 50.8766C69.044 50.8451 69.0695 50.8164 69.0847 50.7903C69.1206 50.7588 69.1695 50.735 69.2314 50.7188C69.3139 50.6971 69.3731 50.6706 69.409 50.6391L69.4399 50.631L69.4481 50.6619L69.4171 50.67L69.3714 50.7482L69.5343 50.7385L69.751 50.6817C69.7716 50.6763 69.7847 50.6839 69.7901 50.7046C69.8943 50.7654 69.9464 50.7959 69.9464 50.7959L69.9545 50.8268L69.9235 50.835C69.9181 50.8143 69.9051 50.8067 69.8844 50.8121C69.8324 50.7817 69.7884 50.7822 69.7525 50.8136C69.7167 50.8451 69.6884 50.8635 69.6678 50.869L69.6531 50.939L69.715 50.9227C69.7769 50.9065 69.8393 50.9342 69.9022 51.006C69.9022 51.006 69.9049 51.0163 69.9103 51.0369C69.931 51.0315 69.9489 51.0158 69.9641 50.9897L70.1189 50.9491C70.1135 50.9285 70.1135 50.9285 70.1189 50.9491C70.1395 50.9437 70.1498 50.941 70.1498 50.941L70.1189 50.9491C70.0472 51.0121 70.0015 51.0902 69.9819 51.1836L69.9281 51.2308C69.7738 51.3153 69.6657 51.3657 69.6038 51.382C69.4181 51.4307 69.2818 51.4995 69.1949 51.5885C69.1079 51.6775 69.0411 51.717 68.9944 51.7072L68.8787 51.7706L68.1095 52.3694L67.8486 52.6363L67.3336 53.0691L67.1037 53.3279L66.812 53.603C66.7609 53.6605 66.7071 53.7077 66.6506 53.7445C66.5941 53.7814 66.5479 53.8156 66.5121 53.847L66.4045 53.9414L66.2071 54.324C66.1919 54.35 66.1951 54.4043 66.2168 54.4869L66.2639 54.5407L66.2492 54.6107C66.2438 54.5901 66.2308 54.5825 66.2102 54.5879C66.1733 54.5314 66.1239 54.5112 66.062 54.5275L65.992 54.5128C65.8096 54.4062 65.7185 54.3529 65.7185 54.3529L65.5393 54.3007L65.4856 54.3478L65.2247 54.6148L65.14 54.6701L64.8563 54.976L64.8188 55.0851C64.7884 55.1372 64.7601 55.1557 64.7341 55.1404C64.7286 55.1198 64.7053 55.1149 64.664 55.1257C64.5565 55.2201 64.4951 55.2803 64.4798 55.3064C64.4646 55.3324 64.4391 55.3612 64.4032 55.3926C64.3674 55.4241 64.3369 55.4762 64.3119 55.5489C64.3281 55.6108 64.3053 55.6499 64.2434 55.6661C64.0891 55.7507 63.9523 55.7756 63.8329 55.7407C63.8068 55.7255 63.7732 55.7233 63.7319 55.7341C63.6287 55.7612 63.4631 55.7605 63.2351 55.7321L63.227 55.7011C63.1749 55.6707 63.1206 55.6739 63.0641 55.7108C63.0283 55.7422 63 55.7607 62.9794 55.7661C62.9283 55.8236 62.8463 55.8892 62.7333 55.963C62.5997 56.0421 62.4965 56.0692 62.4237 56.0442ZM60.5371 54.6533L60.5062 54.6614L60.4362 54.6467C60.4416 54.6673 60.4237 54.6831 60.3824 54.6939L60.4524 54.7086L60.5143 54.6924L60.5371 54.6533ZM60.1774 54.4168C60.2393 54.4006 60.2779 54.3795 60.2931 54.3534L60.324 54.3453L60.2931 54.3534C60.2464 54.3436 60.1715 54.3522 60.0683 54.3793L60.0064 54.3955C60.0064 54.3955 60.0091 54.4058 60.0145 54.4265C60.0145 54.4265 60.0248 54.4238 60.0455 54.4184L60.0845 54.4412L60.1774 54.4168ZM59.9825 53.674C59.9663 53.6121 59.9658 53.5681 59.981 53.542L60.0089 53.2701L59.9927 53.2081L59.9699 53.2472L59.9206 53.6902L59.9597 53.713L59.9825 53.674ZM60.4433 53.917L60.388 53.8323C60.3673 53.8377 60.357 53.8404 60.357 53.8404C60.3516 53.8198 60.3489 53.8094 60.3489 53.8094L60.3717 53.7704C60.3717 53.7704 60.3744 53.7807 60.3798 53.8013C60.3798 53.8013 60.3902 53.7986 60.4108 53.7932L60.4189 53.8242C60.4396 53.8188 60.4499 53.816 60.4499 53.816C60.4445 53.7954 60.4418 53.7851 60.4418 53.7851L60.4387 53.5212C60.4485 53.4745 60.4426 53.4099 60.421 53.3274C60.4514 53.2753 60.4433 53.2443 60.3966 53.2345L60.3885 53.2036L60.3413 53.1498C60.3413 53.1498 60.3261 53.1758 60.2956 53.2279C60.3227 53.3311 60.3237 53.4191 60.2987 53.4918L60.3377 53.5146L60.3687 53.5065L60.4078 53.5293L60.393 53.5994C60.3257 53.595 60.3051 53.6004 60.3311 53.6156C60.3365 53.6362 60.342 53.6569 60.3474 53.6775L60.3783 53.6694L60.3474 53.6775L60.3164 53.6856C60.3218 53.7063 60.3196 53.7399 60.3098 53.7866C60.2794 53.8387 60.2902 53.88 60.3423 53.9104C60.3531 53.9517 60.3689 53.9696 60.3895 53.9642C60.3949 53.9848 60.4079 53.9925 60.4286 53.987L60.4433 53.917ZM61.3795 54.3331C61.462 54.3115 61.5212 54.2849 61.5571 54.2534L61.549 54.2225L61.518 54.2306L61.4333 54.2859L61.4251 54.255L61.3714 54.3022C61.3507 54.3076 61.3431 54.3206 61.3485 54.3412L61.3795 54.3331ZM61.686 53.9881C61.7066 53.9827 61.7169 53.9799 61.7169 53.9799C61.7115 53.9593 61.7088 53.949 61.7088 53.949L61.6778 53.9571C61.6159 53.9734 61.5671 53.9972 61.5312 54.0287L61.5393 54.0596L61.686 53.9881ZM60.8101 53.4238C60.8047 53.4032 60.8123 53.3901 60.833 53.3847C60.8069 53.3695 60.7885 53.3413 60.7777 53.3L60.763 53.37C60.7738 53.4113 60.7895 53.4292 60.8101 53.4238ZM60.0353 52.8661L60.0338 52.7342L60.0028 52.7423L59.9962 52.8433L60.0125 52.9052L60.0353 52.8661ZM60.4768 52.7834C60.4768 52.7834 60.492 52.7574 60.5224 52.7053L60.4524 52.6906L60.4443 52.6596L60.4052 52.6368L60.3743 52.6449L60.3986 52.7378C60.3986 52.7378 60.4247 52.753 60.4768 52.7834ZM61.9661 54.0469L62.6683 53.6973L62.815 53.6258L62.8378 53.5867L62.7759 53.6029L62.1812 53.8582L62.0965 53.9135L62.0736 53.9525L62.0117 53.9688C61.9292 53.9904 61.8521 54.0327 61.7803 54.0956C61.7597 54.1011 61.7521 54.1141 61.7575 54.1347L61.7885 54.1266L61.9661 54.0469ZM62.5313 53.9317C62.5726 53.9209 62.6008 53.9025 62.6161 53.8764L62.5151 53.8698C62.4999 53.8959 62.4716 53.9143 62.4304 53.9251C62.4564 53.9404 62.4901 53.9426 62.5313 53.9317ZM62.5968 53.5507L62.6277 53.5426L62.5887 53.5197C62.3931 53.6151 62.2595 53.6943 62.1878 53.7572L62.1569 53.7653C62.1569 53.7653 62.1596 53.7756 62.165 53.7963C62.165 53.7963 62.1753 53.7936 62.1959 53.7881L62.5968 53.5507ZM60.5128 52.5424C60.4868 52.5272 60.4917 52.5038 60.5275 52.4724L60.5422 52.4024C60.5108 52.3665 60.5179 52.3095 60.5635 52.2314C60.5581 52.2107 60.5657 52.1977 60.5864 52.1923C60.581 52.1716 60.5783 52.1613 60.5783 52.1613C60.5576 52.1667 60.5473 52.1694 60.5473 52.1694C60.5473 52.1694 60.5267 52.1749 60.4854 52.1857L60.5001 52.1157L60.5148 52.0456C60.5094 52.025 60.5067 52.0147 60.5067 52.0147C60.4861 52.0201 60.4758 52.0228 60.4758 52.0228L60.422 52.07C60.4382 52.1319 60.4365 52.2095 60.4169 52.3029L60.456 52.3257L60.425 52.3339C60.4098 52.3599 60.3973 52.3963 60.3875 52.443C60.3777 52.4896 60.3755 52.5233 60.3809 52.5439L60.3971 52.6058L60.4981 52.6124L60.5128 52.5424ZM62.1716 53.6953C62.3617 53.5793 62.485 53.5028 62.5415 53.4659L62.5724 53.4578L62.5415 53.4659L62.1325 53.6725L62.1406 53.7034L62.1716 53.6953ZM60.1272 52.0812C60.1468 51.9878 60.1512 51.9205 60.1404 51.8792L60.1322 51.8482L60.0881 52.0583L60.1272 52.0812ZM62.8703 53.7105C62.9637 53.7301 63.0229 53.7036 63.0479 53.6308C63.0631 53.6048 63.1017 53.5837 63.1636 53.5674L63.2793 53.504C63.2793 53.504 63.2896 53.5013 63.3102 53.4959C63.3515 53.485 63.3667 53.459 63.3559 53.4177L63.3869 53.4096C63.4694 53.388 63.5183 53.3641 63.5335 53.3381L63.5563 53.299L63.4863 53.2843C63.4711 53.3103 63.4428 53.3288 63.4016 53.3396C63.3397 53.3558 63.2989 53.4106 63.2793 53.504L63.0854 53.5217L62.8622 53.6796L62.8703 53.7105ZM60.5524 51.9365C60.5937 51.9257 60.6116 51.91 60.6062 51.8894C60.6214 51.8633 60.6415 51.8139 60.6666 51.7412C60.6709 51.6739 60.6547 51.612 60.6178 51.5555C60.5918 51.5402 60.594 51.5066 60.6244 51.4545C60.619 51.4339 60.6266 51.4208 60.6473 51.4154C60.6625 51.3894 60.6468 51.3714 60.6001 51.3616L60.592 51.3307L60.5382 51.3779L60.5103 51.6498L60.5265 51.7118C60.5211 51.6911 60.5287 51.6781 60.5493 51.6727L60.5722 51.6336L60.5803 51.6646C60.5194 51.7688 60.489 51.8208 60.489 51.8208L60.4824 51.9218L60.5524 51.9365ZM61.0086 51.7838C60.9879 51.7892 60.9776 51.7919 60.9776 51.7919C60.9722 51.7713 60.9695 51.761 60.9695 51.761L60.9776 51.7919C60.9363 51.8028 60.9081 51.8212 60.8929 51.8472L60.901 51.8782L60.9401 51.901L61.0086 51.7838ZM63.672 53.2356C63.7133 53.2247 63.7415 53.2063 63.7568 53.1803L63.7486 53.1493L63.6558 53.1737L63.6639 53.2046L63.571 53.229C63.5971 53.2442 63.6308 53.2464 63.672 53.2356ZM60.6523 51.1825L60.6833 51.1744L60.6752 51.1434C60.6437 51.1076 60.6383 51.0869 60.6589 51.0815C60.6742 51.0555 60.6921 51.0398 60.7127 51.0343C60.7073 51.0137 60.7198 50.9773 60.7503 50.9252C60.7449 50.9046 60.7395 50.884 60.734 50.8633C60.708 50.8481 60.695 50.8405 60.695 50.8405C60.6537 50.8513 60.6385 50.8774 60.6493 50.9186L60.5742 51.1368L60.5986 51.2297L60.6523 51.1825ZM61.997 52.0208L62.033 51.7798L61.994 51.7569C61.994 51.7569 61.9837 51.7596 61.963 51.765C61.963 51.765 61.9657 51.7754 61.9711 51.796L61.9351 52.037L61.9514 52.0989L61.997 52.0208ZM63.4346 52.8347C63.4139 52.8401 63.4036 52.8428 63.4036 52.8428C63.3982 52.8222 63.3955 52.8119 63.3955 52.8119C63.3748 52.8173 63.3569 52.833 63.3417 52.8591C63.3417 52.8591 63.3314 52.8618 63.3107 52.8672C63.3162 52.8878 63.3395 52.8927 63.3808 52.8819L63.4346 52.8347ZM61.0481 51.1779C61.0536 51.1986 61.0666 51.2062 61.0872 51.2008C61.0818 51.1801 61.0791 51.1698 61.0791 51.1698L61.0238 51.0851C61.0031 51.0905 60.9955 51.1035 61.0009 51.1242C61.0118 51.1654 61.0275 51.1834 61.0481 51.1779ZM66.3989 54.803C66.3935 54.7824 66.3908 54.7721 66.3908 54.7721C66.3854 54.7514 66.3979 54.7151 66.4284 54.663C66.4544 54.6782 66.4571 54.6885 66.4365 54.6939C66.4419 54.7146 66.4294 54.7509 66.3989 54.803ZM63.7212 52.7926C63.7419 52.7872 63.7522 52.7845 63.7522 52.7845C63.7468 52.7638 63.7441 52.7535 63.7441 52.7535L63.7131 52.7616C63.6719 52.7725 63.6154 52.8093 63.5436 52.8722L63.5746 52.8641L63.7212 52.7926ZM63.635 52.716C63.6763 52.7051 63.7045 52.6867 63.7197 52.6607C63.7143 52.64 63.691 52.6351 63.6497 52.6459C63.6497 52.6459 63.6345 52.672 63.604 52.7241C63.604 52.7241 63.6067 52.7344 63.6122 52.755C63.6328 52.7496 63.6404 52.7366 63.635 52.716ZM60.7797 50.7852L60.7929 50.5832L60.7685 50.4904C60.7631 50.4697 60.7604 50.4594 60.7604 50.4594C60.7398 50.4648 60.7295 50.4675 60.7295 50.4675C60.7088 50.473 60.7012 50.486 60.7066 50.5066L60.7148 50.5376L60.731 50.5995C60.6691 50.6157 60.649 50.6651 60.6706 50.7476C60.6554 50.7737 60.6608 50.7943 60.6869 50.8095C60.6869 50.8095 60.6972 50.8068 60.7178 50.8014L60.7797 50.7852ZM61.0532 50.945C61.0478 50.9244 61.0554 50.9114 61.076 50.906C61.0706 50.8853 61.0782 50.8723 61.0989 50.8669L61.107 50.8978L61.1151 50.9288L61.1461 50.9207L61.1217 50.8278L61.1136 50.7969C61.0723 50.8077 61.0544 50.8234 61.0598 50.8441L61.037 50.8831L61.0532 50.945ZM63.8288 52.6982C63.9114 52.6766 63.9885 52.6343 64.0602 52.5713L64.0912 52.5632C64.0857 52.5426 64.0727 52.535 64.0521 52.5404L63.8288 52.6982ZM66.0412 54.0698C66.0825 54.059 66.139 54.0221 66.2107 53.9592L66.2335 53.9201L66.2026 53.9282L65.994 54.016C65.9994 54.0366 65.9918 54.0497 65.9712 54.0551L66.0412 54.0698ZM60.8127 50.2803C60.8073 50.2597 60.8149 50.2466 60.8355 50.2412C60.8301 50.2206 60.8377 50.2076 60.8584 50.2022L60.8959 50.0931C60.8699 50.0778 60.8645 50.0572 60.8797 50.0312C60.8949 50.0051 60.9025 49.9921 60.9025 49.9921C60.9113 49.8575 60.9309 49.7641 60.9614 49.712L61.0055 49.5019L60.9893 49.44C60.9578 49.4042 60.9269 49.4123 60.8964 49.4644C60.9018 49.485 60.8947 49.542 60.8751 49.6354L60.8228 49.8145L60.7868 50.0555C60.7672 50.1489 60.7601 50.2059 60.7655 50.2265C60.7503 50.2526 60.7454 50.2759 60.7508 50.2965C60.7562 50.3172 60.7513 50.3405 60.7361 50.3666C60.7415 50.3872 60.7442 50.3975 60.7442 50.3975C60.7236 50.4029 60.7132 50.4056 60.7132 50.4056L60.7833 50.4204L60.8127 50.2803ZM64.0445 51.8807L64.0135 51.8889C63.9929 51.8943 63.9674 51.923 63.9369 51.9751L63.945 52.0061L64.0445 51.8807ZM60.973 49.3781C60.9937 49.3727 61.004 49.37 61.004 49.37C61.0192 49.3439 61.0344 49.3179 61.0497 49.2918L60.9715 49.2462L60.903 49.3634L60.973 49.3781ZM64.5758 51.5098C64.5291 51.5 64.4775 51.5135 64.421 51.5504C64.3797 51.5612 64.3515 51.5797 64.3363 51.6057L64.3215 51.6757L64.3834 51.6595L64.5758 51.5098ZM61.0304 48.9661L61.0695 48.9889C61.064 48.9683 61.0613 48.958 61.0613 48.958C61.082 48.9525 61.0923 48.9498 61.0923 48.9498L61.0842 48.9189L60.9913 48.9432L60.9766 49.0133L61.0304 48.9661ZM64.8381 51.3748C64.8327 51.3542 64.8506 51.3385 64.8919 51.3276L64.7909 51.3211L64.7371 51.3682L64.7143 51.4073L64.7452 51.3992L64.8381 51.3748ZM65.2207 51.5722L65.2973 51.486C65.2821 51.512 65.2538 51.5305 65.2126 51.5413L65.1588 51.5885L65.1278 51.5966L65.1588 51.5885L65.2207 51.5722ZM61.1283 48.7088C61.1229 48.6882 61.1278 48.6648 61.143 48.6388C61.1583 48.6127 61.1528 48.5921 61.1268 48.5769L61.1496 48.5378L61.1791 48.3978C61.1682 48.3565 61.1525 48.3386 61.1319 48.344L61.1172 48.414L61.1024 48.484L61.073 48.6241C61.0784 48.6447 61.0735 48.668 61.0583 48.6941L61.0436 48.7641C61.0436 48.7641 61.0463 48.7744 61.0517 48.7951C61.0723 48.7897 61.0799 48.7766 61.0745 48.756L61.1283 48.7088ZM66.3071 51.5519C66.3277 51.5465 66.3353 51.5335 66.3299 51.5129C66.3093 51.5183 66.2756 51.5161 66.229 51.5063C66.1823 51.4965 66.1513 51.5046 66.1361 51.5306C66.1155 51.536 66.0693 51.5702 65.9976 51.6331L65.9747 51.6722L66.0057 51.6641L66.0676 51.6478L66.0985 51.6397C66.1148 51.7016 66.1305 51.7196 66.1457 51.6935C66.161 51.6675 66.1789 51.6517 66.1995 51.6463L66.3071 51.5519ZM61.2379 48.1177C61.2325 48.097 61.245 48.0607 61.2755 48.0086L61.2283 47.9548L61.1907 48.0639L61.2379 48.1177ZM66.3183 51.8468C66.4627 51.8089 66.5735 51.7688 66.6506 51.7265C66.7636 51.6527 66.8842 51.566 67.0124 51.4662C67.0537 51.4554 67.0716 51.4396 67.0662 51.419L67.0043 51.4352L66.9424 51.4515L66.7957 51.523C66.6665 51.5349 66.5791 51.5798 66.5334 51.658L66.3101 51.8158C66.2895 51.8212 66.2819 51.8342 66.2873 51.8549L66.3183 51.8468ZM65.8616 50.6102L65.8535 50.5792L65.7916 50.5954L65.7068 50.6507L65.684 50.6898L65.754 50.7045L65.8616 50.6102ZM66.1594 50.8629C66.2366 50.8206 66.3468 50.7365 66.4903 50.6107L66.5131 50.5716L66.4512 50.5878L66.3893 50.6041L66.3502 50.5812L66.3583 50.6122C66.3692 50.6535 66.3539 50.6795 66.3127 50.6903C66.2866 50.6751 66.2736 50.6675 66.2736 50.6675L66.2345 50.6447C66.2454 50.6859 66.2611 50.7039 66.2817 50.6984C66.2817 50.6984 66.2844 50.7088 66.2898 50.7294C66.2898 50.7294 66.3002 50.7267 66.3208 50.7213L66.2589 50.7375C66.2437 50.7636 66.2154 50.782 66.1742 50.7928C66.1535 50.7982 66.1356 50.814 66.1204 50.84L66.0975 50.8791L66.1594 50.8629ZM66.9079 49.8064C66.9025 49.7858 66.9101 49.7727 66.9307 49.7673L67.1621 49.6405L67.5158 49.3492L67.5467 49.3411L67.6168 49.3558L67.5939 49.3949C67.5429 49.4524 67.4608 49.518 67.3478 49.5918C67.2348 49.6655 67.168 49.7051 67.1474 49.7105L67.0936 49.7577C67.0317 49.7739 67.0165 49.8 67.0479 49.8358L66.9079 49.8064ZM67.9106 48.584L67.94 48.444C67.9552 48.4179 67.9938 48.3968 68.0557 48.3805L68.0638 48.4115C68.0334 48.4636 68.0518 48.4918 68.1191 48.4962L68.1501 48.4881L68.1191 48.4962L67.9106 48.584ZM69.0736 48.4775C69.053 48.4829 69.0426 48.4856 69.0426 48.4856C69.0372 48.4649 69.0345 48.4546 69.0345 48.4546C68.863 48.3893 68.7615 48.3388 68.7301 48.3029C68.6986 48.267 68.6595 48.2442 68.6128 48.2344C68.5868 48.2192 68.5635 48.2143 68.5428 48.2197L68.3099 48.2146L68.1942 48.278L68.1633 48.2862L68.1942 48.278L68.3018 48.1837L68.4337 48.1821C68.4544 48.1767 68.4674 48.1843 68.4728 48.205C68.4934 48.1996 68.501 48.1865 68.4956 48.1659C68.5109 48.1398 68.5315 48.1344 68.5575 48.1497L68.6276 48.1644C68.862 48.3014 68.9976 48.3981 69.0345 48.4546C69.0552 48.4492 69.0682 48.4568 69.0736 48.4775ZM73.7288 53.0789C73.5834 53.0289 73.4721 53.025 73.395 53.0673C73.3385 53.1041 73.2869 53.1177 73.2402 53.1079C73.1989 53.1187 73.1576 53.1295 73.1164 53.1403C72.9926 53.1728 72.9019 53.1635 72.8444 53.1124C72.8238 53.1178 72.7977 53.1026 72.7663 53.0668C72.7196 53.0569 72.6783 53.0678 72.6424 53.0992C72.5903 53.0688 72.5279 53.041 72.4552 53.016C72.3672 53.017 72.3075 52.9996 72.2761 52.9637C72.2707 52.9431 72.268 52.9328 72.268 52.9328C72.2473 52.9382 72.237 52.9409 72.237 52.9409C72.1078 52.9528 71.9726 52.9 71.8316 52.7826L71.5809 52.5837L71.2993 52.3929L71.2668 52.2691C71.2929 52.2843 71.3135 52.2789 71.3287 52.2528C71.3287 52.2528 71.3314 52.2632 71.3368 52.2838L71.6088 52.3117L71.6398 52.3036C71.6398 52.3036 71.6371 52.2933 71.6317 52.2726C71.6317 52.2726 71.6213 52.2753 71.6007 52.2807L71.2815 52.1991L71.2734 52.1681C71.3147 52.1573 71.3326 52.1415 71.3272 52.1209C71.3218 52.1003 71.3088 52.0927 71.2881 52.0981C71.236 52.0676 71.2252 52.0264 71.2557 51.9743C71.2655 51.9276 71.2677 51.8939 71.2623 51.8733L71.2851 51.8342C71.3057 51.8288 71.3367 51.8207 71.3779 51.8099C71.4192 51.799 71.4556 51.8115 71.487 51.8474C71.4925 51.868 71.5055 51.8757 71.5261 51.8702L71.518 51.8393C71.4659 51.8088 71.4295 51.7963 71.4089 51.8017C71.3883 51.8072 71.3676 51.8126 71.347 51.818C71.3209 51.8028 71.3128 51.7718 71.3226 51.7251L71.3145 51.6942C71.2678 51.6844 71.2364 51.6485 71.2201 51.5866C71.2039 51.5247 71.2034 51.4807 71.2186 51.4547C71.2599 51.4438 71.2778 51.4281 71.2724 51.4075C71.2616 51.3662 71.2508 51.3249 71.2399 51.2837C71.2031 51.2272 71.1895 51.1756 71.1993 51.1289L71.177 50.5393C71.1716 50.5186 71.188 50.371 71.2262 50.0963L71.2511 49.5604L71.3526 48.9383L71.4754 48.1452L71.5784 47.6551C71.5828 47.5877 71.5872 47.5204 71.5916 47.4531C71.5906 47.3652 71.5999 47.2745 71.6195 47.1811L71.6799 47.033L71.7895 46.4418L71.8402 46.1308C71.8176 45.9603 71.8335 45.7686 71.8879 45.5558C71.9218 45.3485 71.9458 45.1878 71.96 45.0738L72.0041 44.8637C72.0326 44.6357 72.0642 44.462 72.099 44.3426C72.1318 44.0473 72.1755 43.7932 72.2299 43.5804C72.2648 43.461 72.2763 43.3367 72.2645 43.2075C72.2516 42.9903 72.2675 42.7987 72.3122 42.6326C72.3524 42.5338 72.3845 42.4041 72.4086 42.2434C72.4326 42.0827 72.4544 41.9557 72.474 41.8623L72.5542 41.4112C72.5826 41.1832 72.6142 41.0095 72.6491 40.8901C72.6883 40.7033 72.7281 40.5606 72.7683 40.4618L72.7602 40.4308L72.8338 40.0807L72.9008 39.8316C72.8998 39.7436 72.9243 39.6269 72.9744 39.4815C72.994 39.3881 73.0033 39.2974 73.0023 39.2095C73.0219 39.1161 73.0491 39.0097 73.084 38.8903C73.1537 38.6515 73.1956 38.4751 73.2098 38.3611C73.358 37.7488 73.4588 37.2923 73.5122 36.9915C73.6212 36.566 73.6898 36.2392 73.7183 36.0112C73.7879 35.7723 73.8272 35.5856 73.836 35.451C73.885 35.2176 73.8852 35.008 73.8365 34.8223C73.8203 34.7604 73.8165 34.6621 73.8253 34.5275C73.8189 34.4189 73.8614 34.2864 73.9527 34.1302L74.1338 33.6856C74.1741 33.5869 74.2605 33.4539 74.3931 33.2868C74.4693 33.1566 74.6567 33.0302 74.9554 32.9078C75.1205 32.8645 75.247 32.8423 75.3349 32.8413C75.3816 32.8511 75.4256 32.8506 75.4669 32.8398C75.5234 32.8029 75.5749 32.7894 75.6216 32.7992C76.0245 32.7376 76.3562 32.7829 76.6167 32.9352L76.9374 33.1488L77.0855 33.2092L77.1327 33.263C77.1175 33.289 77.1299 33.4622 77.1698 33.7826L77.1875 33.9764L77.1972 34.1393C77.2296 34.2631 77.3415 34.311 77.5326 34.2829C77.6151 34.2613 77.6824 34.2657 77.7345 34.2961L77.7427 34.327L77.7117 34.3352L77.526 34.3839C77.4543 34.4468 77.4135 34.5016 77.4037 34.5483L77.2763 34.9456C77.2763 34.9456 77.279 34.9559 77.2844 34.9766C77.2844 34.9766 77.2741 34.9793 77.2535 34.9847C77.1666 35.0736 77.16 35.1746 77.2337 35.2876L77.2271 35.3886C77.2325 35.4092 77.22 35.4456 77.1896 35.4977C77.2058 35.5596 77.2036 35.5932 77.183 35.5987C77.1677 35.6247 77.1471 35.6301 77.1211 35.6149C77.095 35.5997 77.0717 35.5948 77.051 35.6002C76.9891 35.6164 76.9429 35.6506 76.9125 35.7027L76.7476 36.2091C76.6779 36.4479 76.649 36.6319 76.6608 36.7612C76.7149 36.9675 76.6843 37.2292 76.569 37.5462L76.3761 38.3245L76.2341 38.7919L76.1965 38.901C76.2019 38.9216 76.1948 38.9786 76.1752 39.072C76.1654 39.1187 76.1507 39.1887 76.1311 39.2821C76.106 39.3548 76.0837 39.4378 76.0641 39.5312C76.0357 39.7592 76.004 39.9329 75.9692 40.0523C75.9343 40.1717 75.9049 40.3118 75.8809 40.4725C75.8775 40.6277 75.8763 40.7494 75.8773 40.8373L75.8296 41.4122L75.8606 41.4041L75.9585 41.1468C76.0793 40.8505 76.1397 40.7023 76.1397 40.7023C76.2615 40.494 76.513 40.3177 76.8942 40.1736C77.0593 40.1303 77.1804 40.0875 77.2575 40.0452L77.2885 40.0371L77.3895 40.0437C77.3742 40.0697 77.346 40.0882 77.3047 40.099L76.8338 40.3218C76.5558 40.4388 76.3585 40.6118 76.2422 40.8409C76.1508 40.9971 76.0959 41.166 76.0773 41.3473C76.0346 41.6893 75.9497 41.9542 75.8225 42.1419C75.8225 42.1419 75.7388 42.2852 75.5713 42.5717C75.48 42.728 75.3946 42.9489 75.3151 43.2344C75.2454 43.4732 75.2062 43.6599 75.1974 43.7946C75.1189 44.168 75.0703 44.4454 75.0517 44.6268C75.0321 44.7201 75.0049 44.8265 74.97 44.9459C74.9504 45.0393 74.9259 45.156 74.8965 45.2961C74.8714 45.3688 74.8518 45.4621 74.8376 45.5762C74.8234 45.6902 74.8011 45.7732 74.7706 45.8253C74.7205 45.9708 74.6715 46.2042 74.6235 46.5255C74.6235 46.5255 74.6082 46.5516 74.5778 46.6037C74.5886 46.645 74.5788 46.6916 74.5484 46.7437L74.4991 47.1867L74.4433 47.7307L74.3911 47.9098L74.3616 48.0498C74.3724 48.0911 74.3909 48.1194 74.4169 48.1346C74.4115 48.114 74.4191 48.1009 74.4398 48.0955C74.4604 48.0901 74.468 48.0771 74.4626 48.0564L74.5981 47.6901C74.5981 47.6901 74.6133 47.664 74.6438 47.6119L74.6681 47.7048L74.5047 48.3431L74.3885 49.0353C74.3841 49.1026 74.3976 49.1542 74.4291 49.19C74.4552 49.2053 74.4964 49.1944 74.5529 49.1576C74.6148 49.1413 74.674 49.1148 74.7305 49.0779C74.787 49.041 74.8462 49.0145 74.9081 48.9982C75.0059 48.9505 75.1216 48.8871 75.2552 48.8079C75.3834 48.7082 75.4964 48.6344 75.5942 48.5867L75.8631 48.3508L75.9854 48.1864L76.0392 48.1392C76.163 48.1067 76.2271 48.0568 76.2315 47.9895C76.2261 47.9688 76.2234 47.9585 76.2234 47.9585C76.244 47.9531 76.2543 47.9504 76.2543 47.9504L76.2624 47.9814L76.1792 48.1686C76.1488 48.2207 76.1542 48.2413 76.1955 48.2305C76.2161 48.2251 76.2318 48.243 76.2426 48.2843C76.2687 48.2995 76.2893 48.2941 76.3046 48.268L76.6126 48.0549L76.6435 48.0468C76.6641 48.0414 76.6848 48.036 76.7054 48.0306C76.7206 48.0045 76.7125 47.9736 76.6811 47.9377L76.6958 47.8677L76.7496 47.8205C76.8115 47.8043 76.8348 47.8092 76.8196 47.8352L76.8587 47.8581L76.8815 47.819C76.85 47.7831 76.8626 47.7468 76.919 47.7099L77.1423 47.5521L77.2661 47.5196C77.2661 47.5196 77.2792 47.5272 77.3052 47.5424C77.3465 47.5316 77.3617 47.5056 77.3509 47.4643L77.3737 47.4252C77.3997 47.4404 77.4334 47.4426 77.4747 47.4318C77.5105 47.4004 77.5415 47.3922 77.5675 47.4075L77.6213 47.3603C77.667 47.2821 77.6898 47.2431 77.6898 47.2431C77.7051 47.217 77.723 47.2013 77.7436 47.1959C77.7849 47.185 77.8131 47.1666 77.8284 47.1406C77.875 47.1504 77.9136 47.1292 77.944 47.0771C77.9745 47.025 78 46.9963 78.0207 46.9909C78.0619 46.98 78.0978 46.9486 78.1282 46.8965L78.2683 46.9259L78.2455 46.965C78.1781 46.9606 78.1374 47.0154 78.1232 47.1294C78.1025 47.1348 78.0949 47.1478 78.1003 47.1685C78.121 47.1631 78.1313 47.1603 78.1313 47.1603L78.1932 47.1441C78.2182 47.0714 78.2541 47.0399 78.3008 47.0497L78.3546 47.0025C78.3698 46.9765 78.385 46.9504 78.4002 46.9244C78.4361 46.8929 78.4823 46.8588 78.5388 46.8219C78.5594 46.8165 78.5724 46.8241 78.5778 46.8447L78.6169 46.8676C78.6321 46.8415 78.6631 46.8334 78.7098 46.8432C78.751 46.8324 78.7766 46.8036 78.7864 46.7569L78.8402 46.7098C78.9792 46.6512 79.1052 46.5851 79.2182 46.5114C79.3312 46.4376 79.4262 46.3796 79.5034 46.3373L79.6729 46.2267C79.6881 46.2006 79.7087 46.1952 79.7348 46.2105C79.776 46.1996 79.8124 46.2121 79.8439 46.248L79.891 46.3018L79.9301 46.3246L79.9235 46.4256L79.648 46.7625L79.5876 46.9107C79.5778 46.9574 79.5935 46.9753 79.6348 46.9645L79.6739 46.9873C79.6739 46.9873 79.6766 46.9976 79.682 47.0183C79.682 47.0183 79.6717 47.021 79.651 47.0264L79.3902 47.2933C79.2468 47.4191 79.1419 47.5238 79.0756 47.6074C79.0191 47.6443 78.9604 47.7148 78.8995 47.819L78.9076 47.8499L78.9386 47.8418L79.1847 47.6449L79.2157 47.6368C79.1798 47.6683 79.1439 47.6997 79.1081 47.7312C79.0722 47.7627 79.0391 47.8044 79.0086 47.8565C79.0086 47.8565 78.9782 47.9086 78.9173 48.0128L78.8488 48.13L78.7412 48.2244L78.7574 48.2863L78.8194 48.2701L79.0426 48.1123L79.305 47.9773C79.4897 47.8406 79.6412 47.7458 79.7596 47.6926C79.7704 47.7339 79.7682 47.7676 79.753 47.7936C79.753 47.7936 79.7427 47.7963 79.7221 47.8017C79.7167 47.7811 79.7167 47.7811 79.7221 47.8017L79.6911 47.8099C79.7432 47.8403 79.7383 47.8636 79.6764 47.8799L79.6454 47.888L79.5607 47.9433L79.616 48.0281C79.6214 48.0487 79.6241 48.059 79.6241 48.059C79.6448 48.0536 79.6551 48.0509 79.6551 48.0509L80.0331 47.8525L80.0641 47.8444L80.1179 47.7972L80.1031 47.8672L80.1194 47.9291L80.3132 47.9113C80.3491 47.8799 80.3746 47.8511 80.3898 47.8251C80.4257 47.7936 80.4746 47.7698 80.5365 47.7535C80.619 47.7319 80.6782 47.7053 80.7141 47.6739L80.745 47.6658L80.7532 47.6967L80.7222 47.7048L80.6765 47.783L80.8394 47.7733L81.0561 47.7165C81.0767 47.7111 81.0897 47.7187 81.0952 47.7393C81.1993 47.8002 81.2514 47.8307 81.2514 47.8307L81.2596 47.8616L81.2286 47.8697C81.2232 47.8491 81.2102 47.8415 81.1895 47.8469C81.1374 47.8165 81.0935 47.817 81.0576 47.8484C81.0218 47.8799 80.9935 47.8983 80.9729 47.9037L80.9582 47.9738L81.0201 47.9575C81.082 47.9413 81.1444 47.969 81.2073 48.0407C81.2073 48.0407 81.21 48.0511 81.2154 48.0717C81.2361 48.0663 81.254 48.0506 81.2692 48.0245L81.424 47.9839C81.4186 47.9633 81.4186 47.9633 81.424 47.9839C81.4446 47.9785 81.4549 47.9758 81.4549 47.9758L81.424 47.9839C81.3523 48.0468 81.3066 48.125 81.287 48.2183L81.2332 48.2655C81.0789 48.3501 80.9708 48.4005 80.9089 48.4167C80.7232 48.4655 80.5869 48.5343 80.4999 48.6233C80.413 48.7122 80.3462 48.7518 80.2995 48.742L80.1838 48.8054L79.4146 49.4042L79.1537 49.6711L78.6387 50.1039L78.4088 50.3627L78.1171 50.6377C78.066 50.6952 78.0122 50.7424 77.9557 50.7793C77.8992 50.8162 77.853 50.8503 77.8172 50.8818L77.7096 50.9762L77.5122 51.3588C77.497 51.3848 77.5002 51.4391 77.5219 51.5217L77.569 51.5755L77.5543 51.6455C77.5489 51.6248 77.5359 51.6172 77.5153 51.6226C77.4784 51.5662 77.429 51.546 77.3671 51.5623L77.2971 51.5475C77.1147 51.441 77.0236 51.3877 77.0236 51.3877L76.8444 51.3354L76.7907 51.3826L76.5298 51.6495L76.4451 51.7048L76.1614 52.0108L76.1239 52.1199C76.0934 52.172 76.0652 52.1904 76.0392 52.1752C76.0337 52.1546 76.0104 52.1497 75.9691 52.1605C75.8616 52.2549 75.8002 52.3151 75.7849 52.3412C75.7697 52.3672 75.7442 52.396 75.7083 52.4274C75.6725 52.4589 75.642 52.511 75.617 52.5837C75.6332 52.6456 75.6104 52.6847 75.5485 52.7009C75.3942 52.7855 75.2574 52.8103 75.138 52.7755C75.1119 52.7603 75.0783 52.7581 75.037 52.7689C74.9338 52.796 74.7682 52.7953 74.5402 52.7669L74.5321 52.7359C74.48 52.7055 74.4257 52.7087 74.3692 52.7456C74.3334 52.777 74.3051 52.7955 74.2845 52.8009C74.2334 52.8584 74.1514 52.924 74.0384 52.9978C73.9047 53.0769 73.8016 53.104 73.7288 53.0789ZM71.8422 51.6881L71.8113 51.6962L71.7413 51.6815C71.7467 51.7021 71.7287 51.7178 71.6875 51.7287L71.7575 51.7434L71.8194 51.7271L71.8422 51.6881ZM71.4825 51.4516C71.5444 51.4354 71.5829 51.4142 71.5982 51.3882L71.6291 51.3801L71.5982 51.3882C71.5515 51.3784 71.4766 51.387 71.3734 51.4141L71.3115 51.4303C71.3115 51.4303 71.3142 51.4406 71.3196 51.4613C71.3196 51.4613 71.3299 51.4585 71.3505 51.4531L71.3896 51.476L71.4825 51.4516ZM71.2876 50.7087C71.2714 50.6468 71.2709 50.6029 71.2861 50.5768L71.314 50.3048L71.2978 50.2429L71.2749 50.282L71.2257 50.725L71.2648 50.7478L71.2876 50.7087ZM71.7484 50.9518L71.6931 50.8671C71.6724 50.8725 71.6621 50.8752 71.6621 50.8752C71.6567 50.8545 71.654 50.8442 71.654 50.8442L71.6768 50.8052C71.6768 50.8052 71.6795 50.8155 71.6849 50.8361C71.6849 50.8361 71.6953 50.8334 71.7159 50.828L71.724 50.8589C71.7446 50.8535 71.755 50.8508 71.755 50.8508C71.7496 50.8302 71.7468 50.8199 71.7468 50.8199L71.7438 50.556C71.7536 50.5093 71.7477 50.4447 71.726 50.3622C71.7565 50.3101 71.7484 50.2791 71.7017 50.2693L71.6936 50.2384L71.6464 50.1846C71.6464 50.1846 71.6312 50.2106 71.6007 50.2627C71.6278 50.3659 71.6288 50.4538 71.6038 50.5266L71.6428 50.5494L71.6738 50.5413L71.7129 50.5641L71.6981 50.6342C71.6308 50.6298 71.6102 50.6352 71.6362 50.6504C71.6416 50.671 71.6471 50.6917 71.6525 50.7123L71.6834 50.7042L71.6525 50.7123L71.6215 50.7204C71.6269 50.7411 71.6247 50.7747 71.6149 50.8214C71.5845 50.8735 71.5953 50.9148 71.6474 50.9452C71.6582 50.9865 71.6739 51.0044 71.6946 50.999C71.7 51.0196 71.713 51.0272 71.7337 51.0218L71.7484 50.9518ZM72.6846 51.3679C72.7671 51.3462 72.8263 51.3197 72.8622 51.2882L72.854 51.2573L72.8231 51.2654L72.7384 51.3207L72.7302 51.2898L72.6764 51.3369C72.6558 51.3424 72.6482 51.3554 72.6536 51.376L72.6846 51.3679ZM72.9911 51.0228C73.0117 51.0174 73.022 51.0147 73.022 51.0147C73.0166 50.9941 73.0139 50.9838 73.0139 50.9838L72.9829 50.9919C72.921 51.0081 72.8721 51.032 72.8363 51.0634L72.8444 51.0944L72.9911 51.0228ZM72.1152 50.4586C72.1098 50.438 72.1174 50.4249 72.1381 50.4195C72.112 50.4043 72.0936 50.376 72.0828 50.3348L72.068 50.4048C72.0789 50.4461 72.0946 50.464 72.1152 50.4586ZM71.3404 49.9009L71.3389 49.769L71.3079 49.7771L71.3013 49.8781L71.3176 49.94L71.3404 49.9009ZM71.7819 49.8182C71.7819 49.8182 71.7971 49.7922 71.8275 49.7401L71.7575 49.7254L71.7494 49.6944L71.7103 49.6716L71.6794 49.6797L71.7037 49.7725C71.7037 49.7725 71.7298 49.7878 71.7819 49.8182ZM73.2712 51.0817L73.9734 50.7321L74.1201 50.6606L74.1429 50.6215L74.081 50.6377L73.4863 50.8929L73.4016 50.9483L73.3787 50.9873L73.3168 51.0036C73.2343 51.0252 73.1572 51.0675 73.0854 51.1304C73.0648 51.1358 73.0572 51.1489 73.0626 51.1695L73.0936 51.1614L73.2712 51.0817ZM73.8364 50.9665C73.8777 50.9557 73.9059 50.9373 73.9212 50.9112L73.8202 50.9046C73.805 50.9307 73.7767 50.9491 73.7354 50.9599C73.7615 50.9752 73.7952 50.9774 73.8364 50.9665ZM73.9019 50.5855L73.9328 50.5773L73.8938 50.5545C73.6982 50.6499 73.5646 50.7291 73.4929 50.792L73.4619 50.8001C73.4619 50.8001 73.4647 50.8104 73.4701 50.831C73.4701 50.831 73.4804 50.8283 73.501 50.8229L73.9019 50.5855ZM71.8179 49.5772C71.7918 49.562 71.7967 49.5386 71.8326 49.5072L71.8473 49.4371C71.8159 49.4013 71.823 49.3443 71.8686 49.2661C71.8632 49.2455 71.8708 49.2325 71.8915 49.2271C71.8861 49.2064 71.8834 49.1961 71.8834 49.1961C71.8627 49.2015 71.8524 49.2042 71.8524 49.2042C71.8524 49.2042 71.8318 49.2096 71.7905 49.2205L71.8052 49.1504L71.8199 49.0804C71.8145 49.0598 71.8118 49.0495 71.8118 49.0495C71.7912 49.0549 71.7809 49.0576 71.7809 49.0576L71.7271 49.1048C71.7433 49.1667 71.7416 49.2443 71.722 49.3377L71.7611 49.3605L71.7301 49.3686C71.7149 49.3947 71.7024 49.431 71.6926 49.4777C71.6827 49.5244 71.6805 49.5581 71.686 49.5787L71.7022 49.6406L71.8032 49.6472L71.8179 49.5772ZM73.4767 50.7301C73.6668 50.614 73.7901 50.5376 73.8466 50.5007L73.8775 50.4926L73.8466 50.5007L73.4376 50.7072L73.4457 50.7382L73.4767 50.7301ZM71.4323 49.1159C71.4519 49.0226 71.4563 48.9553 71.4454 48.914L71.4373 48.883L71.3932 49.0931L71.4323 49.1159ZM74.1754 50.7453C74.2688 50.7649 74.328 50.7384 74.353 50.6656C74.3682 50.6396 74.4068 50.6184 74.4687 50.6022L74.5844 50.5388C74.5844 50.5388 74.5947 50.5361 74.6153 50.5307C74.6566 50.5198 74.6718 50.4938 74.661 50.4525L74.6919 50.4444C74.7745 50.4227 74.8234 50.3989 74.8386 50.3728L74.8614 50.3338L74.7914 50.3191C74.7762 50.3451 74.7479 50.3635 74.7067 50.3744C74.6448 50.3906 74.604 50.4454 74.5844 50.5388L74.3905 50.5565L74.1673 50.7143L74.1754 50.7453ZM71.8575 48.9713C71.8987 48.9605 71.9167 48.9448 71.9113 48.9241C71.9265 48.8981 71.9466 48.8487 71.9716 48.776C71.976 48.7086 71.9598 48.6467 71.9229 48.5902C71.8969 48.575 71.8991 48.5414 71.9295 48.4893C71.9241 48.4686 71.9317 48.4556 71.9524 48.4502C71.9676 48.4241 71.9519 48.4062 71.9052 48.3964L71.8971 48.3655L71.8433 48.4126L71.8154 48.6846L71.8316 48.7465C71.8262 48.7259 71.8338 48.7129 71.8544 48.7075L71.8773 48.6684L71.8854 48.6993C71.8245 48.8035 71.794 48.8556 71.794 48.8556L71.7874 48.9566L71.8575 48.9713ZM72.3136 48.8186C72.293 48.824 72.2827 48.8267 72.2827 48.8267C72.2773 48.8061 72.2746 48.7958 72.2746 48.7958L72.2827 48.8267C72.2414 48.8375 72.2132 48.856 72.198 48.882L72.2061 48.913L72.2451 48.9358L72.3136 48.8186ZM74.9771 50.2703C75.0184 50.2595 75.0466 50.2411 75.0619 50.215L75.0537 50.1841L74.9609 50.2084L74.969 50.2394L74.8761 50.2637C74.9022 50.279 74.9358 50.2812 74.9771 50.2703ZM71.9574 48.2173L71.9884 48.2092L71.9803 48.1782C71.9488 48.1424 71.9434 48.1217 71.964 48.1163C71.9793 48.0903 71.9972 48.0745 72.0178 48.0691C72.0124 48.0485 72.0249 48.0121 72.0554 47.96C72.05 47.9394 72.0445 47.9188 72.0391 47.8981C72.0131 47.8829 72.0001 47.8753 72.0001 47.8753C71.9588 47.8861 71.9436 47.9122 71.9544 47.9534L71.8793 48.1716L71.9037 48.2645L71.9574 48.2173ZM73.3021 49.0556L73.3381 48.8145L73.2991 48.7917C73.2991 48.7917 73.2888 48.7944 73.2681 48.7998C73.2681 48.7998 73.2708 48.8101 73.2762 48.8308L73.2402 49.0718L73.2564 49.1337L73.3021 49.0556ZM74.7396 49.8695C74.719 49.8749 74.7087 49.8776 74.7087 49.8776C74.7033 49.857 74.7006 49.8466 74.7006 49.8466C74.6799 49.8521 74.662 49.8678 74.6468 49.8938C74.6468 49.8938 74.6365 49.8965 74.6158 49.902C74.6212 49.9226 74.6446 49.9275 74.6859 49.9167L74.7396 49.8695ZM72.3532 48.2127C72.3586 48.2334 72.3717 48.241 72.3923 48.2356C72.3869 48.2149 72.3842 48.2046 72.3842 48.2046L72.3289 48.1199C72.3082 48.1253 72.3006 48.1383 72.306 48.1589C72.3169 48.2002 72.3326 48.2181 72.3532 48.2127ZM77.704 51.8378C77.6986 51.8172 77.6959 51.8068 77.6959 51.8068C77.6905 51.7862 77.703 51.7498 77.7334 51.6977C77.7595 51.713 77.7622 51.7233 77.7416 51.7287C77.747 51.7493 77.7345 51.7857 77.704 51.8378ZM75.0263 49.8274C75.047 49.8219 75.0573 49.8192 75.0573 49.8192C75.0519 49.7986 75.0492 49.7883 75.0492 49.7883L75.0182 49.7964C74.977 49.8072 74.9205 49.8441 74.8487 49.907L74.8797 49.8989L75.0263 49.8274ZM74.9401 49.7507C74.9814 49.7399 75.0096 49.7215 75.0248 49.6954C75.0194 49.6748 74.9961 49.6699 74.9548 49.6807C74.9548 49.6807 74.9396 49.7068 74.9091 49.7589C74.9091 49.7589 74.9118 49.7692 74.9172 49.7898C74.9379 49.7844 74.9455 49.7714 74.9401 49.7507ZM72.0848 47.82L72.098 47.618L72.0736 47.5252C72.0682 47.5045 72.0655 47.4942 72.0655 47.4942C72.0449 47.4996 72.0346 47.5023 72.0346 47.5023C72.0139 47.5077 72.0063 47.5208 72.0117 47.5414L72.0199 47.5724L72.0361 47.6343C71.9742 47.6505 71.9541 47.6999 71.9757 47.7824C71.9605 47.8085 71.9659 47.8291 71.9919 47.8443C71.9919 47.8443 72.0023 47.8416 72.0229 47.8362L72.0848 47.82ZM72.3583 47.9798C72.3529 47.9592 72.3605 47.9462 72.3811 47.9407C72.3757 47.9201 72.3833 47.9071 72.404 47.9017L72.4121 47.9326L72.4202 47.9636L72.4512 47.9555L72.4268 47.8626L72.4187 47.8316C72.3774 47.8425 72.3595 47.8582 72.3649 47.8788L72.3421 47.9179L72.3583 47.9798ZM75.1339 49.733C75.2165 49.7113 75.2936 49.669 75.3653 49.6061L75.3963 49.598C75.3908 49.5774 75.3778 49.5698 75.3572 49.5752L75.1339 49.733ZM77.3463 51.1046C77.3876 51.0937 77.444 51.0569 77.5158 50.9939L77.5386 50.9549L77.5076 50.963L77.2991 51.0508C77.3045 51.0714 77.2969 51.0844 77.2763 51.0898L77.3463 51.1046ZM72.1178 47.3151C72.1124 47.2945 72.12 47.2814 72.1406 47.276C72.1352 47.2554 72.1428 47.2424 72.1635 47.2369L72.201 47.1278C72.175 47.1126 72.1695 47.092 72.1848 47.0659C72.2 47.0399 72.2076 47.0269 72.2076 47.0269C72.2164 46.8922 72.236 46.7989 72.2665 46.7468L72.3106 46.5367L72.2944 46.4748C72.2629 46.4389 72.232 46.4471 72.2015 46.4991C72.2069 46.5198 72.1998 46.5768 72.1802 46.6701L72.1279 46.8493L72.0919 47.0903C72.0723 47.1837 72.0652 47.2407 72.0706 47.2613C72.0554 47.2873 72.0505 47.3107 72.0559 47.3313C72.0613 47.352 72.0564 47.3753 72.0412 47.4013C72.0466 47.422 72.0493 47.4323 72.0493 47.4323C72.0287 47.4377 72.0183 47.4404 72.0183 47.4404L72.0884 47.4551L72.1178 47.3151ZM75.3496 48.9155L75.3186 48.9236C75.298 48.9291 75.2724 48.9578 75.242 49.0099L75.2501 49.0409L75.3496 48.9155ZM72.2781 46.4129C72.2988 46.4075 72.3091 46.4048 72.3091 46.4048C72.3243 46.3787 72.3395 46.3527 72.3548 46.3266L72.2766 46.281L72.2081 46.3982L72.2781 46.4129ZM75.8809 48.5446C75.8342 48.5348 75.7826 48.5483 75.7261 48.5852C75.6848 48.596 75.6566 48.6144 75.6413 48.6405L75.6266 48.7105L75.6885 48.6943L75.8809 48.5446ZM72.3355 46.0009L72.3746 46.0237C72.3691 46.0031 72.3664 45.9927 72.3664 45.9927C72.3871 45.9873 72.3974 45.9846 72.3974 45.9846L72.3893 45.9537L72.2964 45.978L72.2817 46.048L72.3355 46.0009ZM76.1432 48.4096C76.1378 48.389 76.1557 48.3733 76.197 48.3624L76.096 48.3558L76.0422 48.403L76.0194 48.4421L76.0503 48.434L76.1432 48.4096ZM76.5258 48.607L76.6024 48.5207C76.5872 48.5468 76.5589 48.5652 76.5177 48.5761L76.4639 48.6232L76.4329 48.6314L76.4639 48.6232L76.5258 48.607ZM72.4334 45.7436C72.428 45.723 72.4329 45.6996 72.4481 45.6736C72.4634 45.6475 72.4579 45.6269 72.4319 45.6117L72.4547 45.5726L72.4842 45.4325C72.4733 45.3913 72.4576 45.3733 72.437 45.3788L72.4223 45.4488L72.4075 45.5188L72.3781 45.6589C72.3835 45.6795 72.3786 45.7028 72.3634 45.7289L72.3487 45.7989C72.3487 45.7989 72.3514 45.8092 72.3568 45.8299C72.3774 45.8244 72.385 45.8114 72.3796 45.7908L72.4334 45.7436ZM77.6122 48.5867C77.6328 48.5813 77.6404 48.5683 77.635 48.5476C77.6144 48.5531 77.5807 48.5509 77.534 48.541C77.4874 48.5312 77.4564 48.5394 77.4412 48.5654C77.4205 48.5708 77.3744 48.605 77.3027 48.6679L77.2798 48.707L77.3108 48.6989L77.3727 48.6826L77.4036 48.6745C77.4199 48.7364 77.4356 48.7543 77.4508 48.7283C77.466 48.7022 77.484 48.6865 77.5046 48.6811L77.6122 48.5867ZM72.543 45.1524C72.5376 45.1318 72.5501 45.0954 72.5806 45.0433L72.5334 44.9896L72.4958 45.0987L72.543 45.1524ZM77.6233 48.8815C77.7678 48.8436 77.8786 48.8036 77.9557 48.7613C78.0687 48.6875 78.1893 48.6008 78.3175 48.501C78.3588 48.4901 78.3767 48.4744 78.3713 48.4538L78.3094 48.47L78.2475 48.4863L78.1008 48.5578C77.9716 48.5696 77.8842 48.6146 77.8385 48.6928L77.6152 48.8506C77.5946 48.856 77.587 48.869 77.5924 48.8897L77.6233 48.8815ZM77.1667 47.6449L77.1586 47.614L77.0966 47.6302L77.0119 47.6855L76.9891 47.7246L77.0591 47.7393L77.1667 47.6449ZM77.4645 47.8976C77.5417 47.8553 77.6519 47.7713 77.7954 47.6454L77.8182 47.6064L77.7563 47.6226L77.6944 47.6388L77.6553 47.616L77.6634 47.647C77.6743 47.6882 77.659 47.7143 77.6178 47.7251C77.5917 47.7099 77.5787 47.7023 77.5787 47.7023L77.5396 47.6794C77.5505 47.7207 77.5662 47.7386 77.5868 47.7332C77.5868 47.7332 77.5895 47.7435 77.5949 47.7642C77.5949 47.7642 77.6053 47.7615 77.6259 47.7561L77.564 47.7723C77.5488 47.7983 77.5205 47.8168 77.4792 47.8276C77.4586 47.833 77.4407 47.8488 77.4255 47.8748L77.4026 47.9139L77.4645 47.8976ZM78.213 46.8412C78.2076 46.8205 78.2152 46.8075 78.2358 46.8021L78.4672 46.6752L78.8209 46.384L78.8518 46.3759L78.9219 46.3906L78.899 46.4297C78.8479 46.4872 78.7659 46.5528 78.6529 46.6265C78.5399 46.7003 78.4731 46.7399 78.4525 46.7453L78.3987 46.7925C78.3368 46.8087 78.3216 46.8347 78.353 46.8706L78.213 46.8412ZM79.2157 45.6188L79.2451 45.4787C79.2603 45.4527 79.2989 45.4316 79.3608 45.4153L79.3689 45.4463C79.3385 45.4984 79.3569 45.5266 79.4242 45.531L79.4552 45.5229L79.4242 45.531L79.2157 45.6188ZM80.3787 45.5122C80.358 45.5177 80.3477 45.5204 80.3477 45.5204C80.3423 45.4997 80.3396 45.4894 80.3396 45.4894C80.1681 45.4241 80.0666 45.3735 80.0352 45.3377C80.0037 45.3018 79.9646 45.279 79.9179 45.2692C79.8919 45.254 79.8686 45.2491 79.8479 45.2545L79.615 45.2494L79.4993 45.3128L79.4684 45.3209L79.4993 45.3128L79.6069 45.2184L79.7388 45.2169C79.7595 45.2115 79.7725 45.2191 79.7779 45.2397C79.7985 45.2343 79.8061 45.2213 79.8007 45.2007C79.816 45.1746 79.8366 45.1692 79.8626 45.1844L79.9327 45.1992C80.1671 45.3362 80.3027 45.4329 80.3396 45.4894C80.3602 45.484 80.3733 45.4916 80.3787 45.5122ZM86.9042 49.0608C86.8011 49.0878 86.6974 49.0709 86.5932 49.01L86.4613 49.0115C86.3168 49.0494 86.1795 49.0303 86.0492 48.9542C85.9613 48.9552 85.8782 48.9329 85.8001 48.8872C85.7013 48.847 85.59 48.8431 85.4662 48.8755C85.451 48.9016 85.4097 48.9124 85.3424 48.908C85.2751 48.9036 85.2208 48.9068 85.1795 48.9177L84.7284 48.8375C84.5352 48.6896 84.335 48.5988 84.1276 48.565C83.9876 48.5356 83.8866 48.529 83.8247 48.5452C83.7215 48.5723 83.633 48.5293 83.5593 48.4163C83.5018 48.3652 83.359 48.3255 83.131 48.2971C82.9497 48.2785 82.718 48.1518 82.4359 47.917C82.3783 47.8659 82.2183 47.6763 81.9558 47.3482C81.8821 47.2352 81.842 47.1244 81.8356 47.0158L81.8046 47.0239L81.8082 46.6591C81.8061 46.4832 81.797 46.3643 81.7808 46.3024L81.7777 46.0385C81.8082 45.9864 81.8229 45.9164 81.8219 45.8284C81.8209 45.7405 81.8176 45.6862 81.8122 45.6656C81.7341 45.6199 81.6999 45.5737 81.7097 45.527C81.7348 45.4543 81.7446 45.4076 81.7392 45.387C81.7219 45.2371 81.741 45.0998 81.7965 44.9749C81.8151 44.7936 81.8256 44.5814 81.828 44.3381C81.8215 44.2295 81.8429 44.0585 81.8919 43.8251C81.9115 43.7318 81.9677 43.4413 82.0604 42.9539C82.0682 42.7313 82.0868 42.55 82.1162 42.4099C82.1402 42.2492 82.1593 42.1119 82.1735 41.9979C82.2334 41.8057 82.2749 41.5853 82.2979 41.3367C82.374 41.2065 82.3904 41.0588 82.3471 40.8937L82.3456 40.7618L82.3816 40.5208C82.4022 40.5154 82.4202 40.4996 82.4354 40.4736C82.4506 40.4475 82.4555 40.4242 82.4501 40.4036L82.4876 40.2945C82.5661 39.921 82.6049 39.6903 82.6038 39.6023C82.6485 39.4362 82.6855 39.2832 82.715 39.1431C82.739 38.9824 82.7608 38.8554 82.7804 38.762L82.8982 38.2018C82.9026 38.1345 82.9141 38.0102 82.9327 37.8289C82.9513 37.6476 82.9856 37.4842 83.0357 37.3387C83.0901 37.1259 83.1114 36.9549 83.0996 36.8257L83.1554 36.2817C83.1957 36.183 83.218 36.0999 83.2224 36.0326C83.2214 35.9446 83.2258 35.8773 83.2356 35.8306C83.2194 35.7687 83.226 35.6678 83.2554 35.5277C83.2913 35.4962 83.2935 35.4626 83.262 35.4267C83.2458 35.3648 83.2246 35.3263 83.1986 35.311L82.9804 35.2359C82.975 35.2153 82.9592 35.1974 82.9332 35.1821C82.9224 35.1409 82.9246 35.1072 82.9398 35.0812C82.9127 34.978 82.8731 34.9112 82.821 34.8807L82.8048 34.8188L82.7723 34.695C82.6932 34.5614 82.7128 34.468 82.8312 34.4149C82.8616 34.3628 82.923 34.3026 83.0154 34.2343C83.236 34.0661 83.4071 33.8779 83.5289 33.6695C83.5702 33.6587 83.5827 33.6223 83.5665 33.5604L83.6273 32.7835C83.6372 32.7369 83.6263 32.6956 83.5949 32.6597C83.5841 32.6185 83.5808 32.5642 83.5852 32.4969C83.595 32.4502 83.6071 32.3698 83.6213 32.2558C83.6507 32.1158 83.7013 32.0143 83.773 31.9514C83.8795 31.769 84.0463 31.6481 84.2733 31.5886C84.4797 31.5344 84.6371 31.5042 84.7457 31.4977C84.8543 31.4913 84.9737 31.5262 85.104 31.6023C85.1713 31.6067 85.2413 31.6214 85.314 31.6464C85.3868 31.6714 85.4568 31.6862 85.5241 31.6906C85.5556 31.7264 85.618 31.7542 85.7114 31.7738C85.8254 31.788 85.9057 31.8 85.9524 31.8098L86.2878 31.9534C86.3399 31.9839 86.3969 31.991 86.4588 31.9747C86.6489 31.8587 86.795 31.7432 86.8972 31.6282C87.2764 31.3081 87.6458 31.0348 88.0054 30.8082C88.251 30.5673 88.5074 30.3677 88.7747 30.2094C89.0159 30.0359 89.219 29.9274 89.3841 29.8841L89.6008 29.8273L89.8794 29.7542C89.9 29.7488 89.9543 29.7456 90.0422 29.7446C90.1248 29.723 90.1948 29.7377 90.2523 29.7888C90.2784 29.804 90.312 29.8062 90.3533 29.7954C90.3946 29.7845 90.4385 29.784 90.4852 29.7938C90.5113 29.8091 90.5449 29.8112 90.5862 29.8004C90.6068 29.795 90.6199 29.8026 90.6253 29.8233L90.5943 29.8314C90.5737 29.8368 90.5557 29.8525 90.5405 29.8786C90.5459 29.8992 90.5486 29.9095 90.5486 29.9095L90.5958 29.9633L90.573 30.0024L90.6283 30.0871L90.8531 30.0612C90.8531 30.0612 90.8791 30.0765 90.9312 30.1069C90.9573 30.1221 90.986 30.1477 91.0175 30.1835C91.0436 30.1988 91.075 30.2346 91.1119 30.2911C91.1281 30.353 91.1596 30.3889 91.2063 30.3987C91.2529 30.4085 91.2893 30.421 91.3154 30.4362C91.336 30.4308 91.3805 30.4743 91.4488 30.5666C91.4955 30.5765 91.5319 30.589 91.5579 30.6042C91.6046 30.614 91.641 30.6265 91.667 30.6417C91.7712 30.7026 91.8162 30.7901 91.802 30.9041C91.8345 31.0279 91.8485 31.1235 91.8441 31.1908L91.9238 31.3684C91.966 31.4455 91.9877 31.528 91.9887 31.616L91.9933 32.0118L91.9572 32.2528L91.8953 32.2691C91.8432 32.2386 91.827 32.1767 91.8466 32.0833C91.8619 32.0573 91.8641 32.0236 91.8532 31.9824C91.837 31.9205 91.8158 31.8819 91.7898 31.8667C91.7583 31.8308 91.7269 31.7949 91.6954 31.7591C91.664 31.7232 91.607 31.7161 91.5244 31.7378C91.5038 31.7432 91.4989 31.7665 91.5097 31.8078L91.495 31.8778L91.4787 31.8159C91.4527 31.8007 91.4316 31.7621 91.4153 31.7002L91.2296 31.7489L91.1367 31.7733C91.0694 31.7689 90.9869 31.7905 90.8891 31.8382C90.6327 32.0378 90.4377 32.1772 90.3041 32.2564C90.0835 32.4245 89.7499 32.6664 89.3034 32.982C88.9232 33.214 88.651 33.3957 88.487 33.5269C88.3946 33.5953 88.2561 33.6978 88.0714 33.8344C87.8813 33.9505 87.7167 34.0378 87.5777 34.0963C87.5212 34.1331 87.4571 34.183 87.3853 34.246C87.3288 34.2828 87.2647 34.3327 87.193 34.3957C87.08 34.4694 87.0235 34.5063 87.0235 34.5063C86.9106 34.58 86.8128 34.6277 86.7302 34.6494C86.715 34.6754 86.6792 34.7069 86.6227 34.7437C86.5608 34.76 86.5325 34.7784 86.5379 34.7991L86.5166 34.9701L86.4314 35.6541C86.4117 35.7474 86.3796 35.8772 86.335 36.0433C86.3055 36.1833 86.2864 36.3207 86.2776 36.4553C86.2286 36.6887 86.1996 36.8727 86.1908 37.0074C86.1614 37.1474 86.1217 37.2902 86.0716 37.4356C86.0422 37.5757 86.0154 37.7261 85.9914 37.8867L85.9392 38.0659L85.9473 38.0968L86.0092 38.0806L86.34 37.8284C86.4584 37.7753 86.5719 37.7455 86.6805 37.7391C86.7272 37.7489 86.8537 37.7267 87.0601 37.6726C87.122 37.6564 87.1714 37.6765 87.2082 37.733C87.2343 37.7482 87.2679 37.7504 87.3092 37.7396C87.5112 37.7528 87.6328 37.754 87.674 37.7431L87.6903 37.805L87.6593 37.8132C87.6387 37.8186 87.6311 37.8316 87.6365 37.8522C87.6419 37.8729 87.6343 37.8859 87.6137 37.8913C87.6343 37.8859 87.6473 37.8935 87.6527 37.9141C87.6581 37.9348 87.6712 37.9424 87.6918 37.937L87.9166 37.9111L87.9475 37.903L88.0957 37.9634L87.9881 38.0577C87.9056 38.0794 87.8567 38.1032 87.8415 38.1293L87.8105 38.1374C87.816 38.158 87.829 38.1657 87.8496 38.1602L87.9506 38.1668L88.2601 38.0857C88.3014 38.0748 88.3687 38.0792 88.4621 38.0989C88.5304 38.1912 88.5982 38.2396 88.6656 38.244L88.8594 38.2262C88.9267 38.2306 88.9658 38.2534 88.9766 38.2947C88.982 38.3154 88.9744 38.3284 88.9538 38.3338L88.6899 38.3368L88.628 38.3531C88.6486 38.3477 88.6617 38.3553 88.6671 38.3759C88.7039 38.4324 88.7587 38.4732 88.8315 38.4982C88.9194 38.4972 88.9868 38.5016 89.0334 38.5114L89.377 38.6859C89.377 38.6859 89.3797 38.6963 89.3851 38.7169C89.3851 38.7169 89.3954 38.7142 89.416 38.7088L89.3232 38.7331C89.3178 38.7125 89.3047 38.7049 89.2841 38.7103C89.2635 38.7157 89.2532 38.7184 89.2532 38.7184C89.2109 38.6413 89.1848 38.6261 89.175 38.6728C89.1598 38.6988 89.1419 38.7145 89.1212 38.7199L89.1846 38.8356L89.3719 38.9189C89.3719 38.9189 89.3746 38.9292 89.38 38.9498C89.4061 38.965 89.4294 38.9699 89.45 38.9645C89.4088 38.9753 89.3621 38.9655 89.31 38.9351L89.279 38.9432C89.279 38.9432 89.2584 38.9486 89.2171 38.9594L89.2724 39.0442C89.4483 39.0422 89.5754 39.064 89.6535 39.1096L89.8651 39.2857L89.9432 39.3314C89.9899 39.3412 89.998 39.3722 89.9676 39.4243C89.9524 39.4503 89.9241 39.4687 89.8829 39.4796L89.6728 39.4354L89.3699 39.4156C89.2765 39.396 89.264 39.4324 89.3323 39.5247L89.3404 39.5557L89.3014 39.5328C89.2699 39.497 89.2156 39.5002 89.1385 39.5425L88.2667 40.0027L87.4569 40.4467L87.2336 40.6045C86.9457 40.7682 86.6654 40.9189 86.3928 41.0566C86.295 41.1043 86.2 41.1623 86.1076 41.2307C86.0098 41.2784 85.8914 41.3315 85.7524 41.39C85.7111 41.4008 85.6443 41.4404 85.552 41.5087C85.4542 41.5564 85.3537 41.5938 85.2506 41.6209L85.1739 41.7071C85.1465 42.0231 85.1127 42.2305 85.0725 42.3292L84.9892 42.5165C84.9304 42.7966 84.872 43.1207 84.8142 43.4887C84.7847 43.6288 84.7607 43.7894 84.7421 43.9708C84.7387 44.126 84.7071 44.2997 84.6472 44.4919C84.5924 45.1238 84.566 45.5277 84.5681 45.7036C84.5691 45.7916 84.5728 45.8898 84.5792 45.9984C84.5802 46.0864 84.597 46.1923 84.6295 46.3161C84.6305 46.404 84.6695 46.4269 84.7467 46.3846C84.7978 46.3271 84.8439 46.2929 84.8852 46.2821C84.9417 46.2452 84.9803 46.2241 85.0009 46.2187L85.0318 46.2105C85.0112 46.216 85.0036 46.229 85.009 46.2496L84.7401 46.4856C84.7194 46.491 84.7015 46.5067 84.6863 46.5328C84.6863 46.5328 84.676 46.5355 84.6553 46.5409L84.7791 46.5084L85.0187 46.4125L85.0806 46.3963L85.0577 46.4353L84.8035 46.6013C84.747 46.6381 84.7139 46.6799 84.704 46.7266C84.6888 46.7526 84.6996 46.7939 84.7365 46.8504C84.7419 46.871 84.7473 46.8917 84.7528 46.9123C84.7734 46.9069 84.7864 46.9145 84.7918 46.9351C84.8027 46.9764 84.8493 46.9862 84.9319 46.9646L85.1714 46.8687C85.2279 46.8318 85.2947 46.7922 85.3718 46.7499C85.4642 46.6816 85.5619 46.6339 85.6651 46.6068L85.727 46.5906C85.7477 46.5852 85.7683 46.5798 85.7889 46.5744C85.8302 46.5635 85.8639 46.5657 85.8899 46.581C85.9941 46.6419 86.0717 46.6435 86.1228 46.586L87.0012 46.0248L87.363 45.7645L87.4249 45.7483C87.4661 45.7375 87.5226 45.7006 87.5943 45.6377C87.6661 45.5747 87.7405 45.5221 87.8176 45.4799C87.8535 45.4484 87.9073 45.4012 87.979 45.3383C88.0659 45.2493 88.1583 45.181 88.256 45.1333C88.2767 45.1279 88.3973 45.0411 88.6178 44.873C88.7308 44.7992 88.8128 44.7336 88.8639 44.6761C88.9356 44.6132 88.9998 44.5633 89.0562 44.5264C89.2159 44.4625 89.293 44.4202 89.2876 44.3996L89.3023 44.3295C89.323 44.3241 89.336 44.3317 89.3414 44.3524C89.3468 44.373 89.3495 44.3833 89.3495 44.3833C89.3952 44.3052 89.4289 44.3074 89.4505 44.3899C89.4766 44.4051 89.4999 44.41 89.5205 44.4046C89.5618 44.3938 89.5797 44.3781 89.5743 44.3574L89.6053 44.3493L89.6672 44.3331L89.6591 44.3021L89.6428 44.2402C89.6374 44.2196 89.645 44.2066 89.6657 44.2012L89.6738 44.2321L89.6981 44.325C89.6981 44.325 89.6829 44.351 89.6525 44.4031L89.6687 44.465C89.6741 44.4857 89.6795 44.5063 89.6849 44.5269C89.7056 44.5215 89.7186 44.5291 89.724 44.5498C89.7501 44.565 89.8228 44.59 89.9422 44.6249C89.9628 44.6194 89.9759 44.6271 89.9813 44.6477C90.1071 44.7911 90.201 44.8547 90.2629 44.8385C90.2835 44.8331 90.2911 44.82 90.2857 44.7994C90.301 44.7734 90.3189 44.7576 90.3395 44.7522L90.3624 44.7131C90.3624 44.7131 90.3651 44.7235 90.3705 44.7441C90.3911 44.7387 90.4117 44.7333 90.4324 44.7279L90.4405 44.7588L90.473 44.8826C90.4936 44.8772 90.5192 44.8485 90.5496 44.7964C90.58 44.7443 90.5926 44.7079 90.5871 44.6873C90.5871 44.6873 90.5844 44.677 90.579 44.6563C90.5943 44.6303 90.5992 44.6069 90.5937 44.5863C90.6144 44.5809 90.6274 44.5885 90.6328 44.6091C90.6382 44.6298 90.6513 44.6374 90.6719 44.632L90.68 44.6629C90.6496 44.715 90.6528 44.7693 90.6896 44.8258C90.7157 44.841 90.7368 44.8796 90.7531 44.9415C90.8214 45.0338 90.8914 45.0486 90.9631 44.9856C91.0196 44.9488 91.0712 44.9352 91.1179 44.945C91.2015 45.0114 91.2285 45.1145 91.1991 45.2546C91.1328 45.3381 91.1208 45.4185 91.1631 45.4956C91.2054 45.5727 91.2292 45.6216 91.2346 45.6422L91.3158 45.9518L91.293 45.9909C91.293 45.9909 91.2827 45.9936 91.262 45.999C91.2414 46.0044 91.2284 45.9968 91.2229 45.9761C91.1556 45.9717 91.1035 45.9413 91.0667 45.8848C91.0352 45.8489 91.0119 45.844 90.9966 45.8701C90.9466 46.0155 90.8238 46.136 90.6282 46.2314C90.5359 46.2997 90.4229 46.3734 90.2893 46.4526C90.1763 46.5263 90.0557 46.6131 89.9275 46.7129C89.8145 46.7867 89.6966 46.8837 89.5738 47.0042L89.5429 47.0123C89.4962 47.0025 89.4576 47.0236 89.4272 47.0757C89.3967 47.1278 89.3712 47.1566 89.3505 47.162L89.3277 47.2011L89.2039 47.2335C89.1995 47.3008 89.1691 47.3529 89.1126 47.3898C89.0561 47.4267 89.0175 47.4478 88.9969 47.4532L88.8193 47.5329C88.7063 47.6067 88.6351 47.7135 88.6056 47.8536L88.5747 47.8617C88.5128 47.878 88.4356 47.9202 88.3433 47.9886C88.2509 48.0569 88.1765 48.1095 88.12 48.1464L87.9049 48.3351C87.8842 48.3406 87.8587 48.3693 87.8283 48.4214C87.7664 48.4376 87.7354 48.4458 87.7354 48.4458L87.6735 48.462C87.6116 48.4782 87.5448 48.5178 87.4731 48.5807C87.4068 48.6643 87.3454 48.7245 87.2889 48.7614L87.1894 48.8867L86.9971 49.0364L86.9042 49.0608ZM85.3977 46.9747L85.4434 46.8966L85.3815 46.9128C85.3196 46.9291 85.2837 46.9605 85.2739 47.0072L85.2511 47.0463L85.313 47.03L85.3977 46.9747ZM82.9854 45.0932L82.9839 44.9612C82.9785 44.9406 82.9654 44.933 82.9448 44.9384L82.9529 44.9694C82.9377 44.9954 82.9382 45.0394 82.9545 45.1013L82.9854 45.0932ZM85.6438 46.7778C85.747 46.7508 85.8165 46.7215 85.8524 46.6901L85.8833 46.6819L85.8442 46.6591L85.6438 46.7778L85.6128 46.786C85.6128 46.786 85.6156 46.7963 85.621 46.8169C85.6416 46.8115 85.6492 46.7985 85.6438 46.7778ZM83.0184 44.5883C83.0488 44.5362 83.0559 44.4792 83.0397 44.4173L83.0316 44.3863L83.0006 44.3945L82.9712 44.5345L82.9874 44.5964L83.0184 44.5883ZM88.1733 46.7099C88.1831 46.6632 88.1983 46.6371 88.219 46.6317C88.2396 46.6263 88.2575 46.6106 88.2728 46.5845L88.5727 46.3405C88.6346 46.3242 88.7014 46.2846 88.7731 46.2217L88.7878 46.1517L88.734 46.1989C88.5385 46.2943 88.3973 46.3865 88.3103 46.4754C88.2799 46.5275 88.2288 46.585 88.1571 46.648C88.1364 46.6534 88.1315 46.6767 88.1424 46.718L88.1733 46.7099ZM88.0191 46.1218C88.1266 46.0274 88.2369 45.9433 88.3499 45.8696C88.4629 45.7958 88.5552 45.7275 88.627 45.6646L88.6807 45.6174C88.6395 45.6282 88.6188 45.6336 88.6188 45.6336L88.2489 45.863C88.2131 45.8944 88.1696 45.9389 88.1185 45.9964C88.0827 46.0279 88.0392 46.0724 87.9881 46.1299L87.9572 46.138L87.9881 46.1299L88.0191 46.1218ZM88.9416 45.3505C89.0752 45.2713 89.1751 45.19 89.2415 45.1064L89.3653 45.0739L89.2024 45.0836C89.1002 45.1986 89.0106 45.2772 88.9334 45.3195C88.9334 45.3195 88.9362 45.3298 88.9416 45.3505C88.9416 45.3505 88.9312 45.3532 88.9106 45.3586L88.9416 45.3505ZM91.5371 32.1645L91.5209 32.1026C91.5046 32.0407 91.5041 31.9967 91.5193 31.9707L91.5503 31.9626L91.5762 32.1874L91.5452 32.1955L91.5371 32.1645ZM94.6393 46.668L94.5774 46.6843C94.4014 46.6863 94.2825 46.6954 94.2206 46.7117L94.1587 46.7279C94.0968 46.7441 93.9931 46.7272 93.8477 46.6772L93.3332 46.4813C93.2191 46.4671 93.1442 46.4757 93.1084 46.5072C93.0465 46.5234 92.984 46.4957 92.9211 46.4239C92.8897 46.3881 92.8577 46.3083 92.8252 46.1844C92.7992 46.1692 92.7834 46.1513 92.778 46.1307C92.7672 46.0894 92.7488 46.0611 92.7227 46.0459C92.6598 45.9742 92.5752 45.8199 92.469 45.5831L92.4365 45.4593L92.3295 44.925C92.2906 44.6926 92.3256 44.3636 92.4345 43.9381C92.6544 43.2629 92.7742 42.8786 92.7938 42.7852C92.8536 42.5931 93.0397 42.1252 93.3519 41.3817L93.6782 40.7337L93.9213 40.2729L94.1887 39.9051C94.2496 39.8009 94.336 39.6679 94.448 39.5062C94.5806 39.3391 94.6589 39.1752 94.6829 39.0145C94.7026 38.9212 94.707 38.8538 94.6961 38.8126C94.6799 38.7507 94.6946 38.6806 94.7403 38.6025C94.8066 38.5189 94.8957 38.3963 95.0077 38.2346C95.1142 38.0523 95.2316 37.9112 95.3598 37.8114C95.4109 37.7539 95.4539 37.6655 95.4887 37.546C95.5084 37.4527 95.5948 37.3197 95.748 37.1472C95.748 37.1472 95.7583 37.1445 95.779 37.1391C95.7996 37.1337 95.823 37.1386 95.849 37.1538L95.9566 37.0594C96.0175 36.9552 96.0398 36.8722 96.0236 36.8103C96.0236 36.8103 96.0464 36.7712 96.0921 36.6931C96.0867 36.6724 96.0839 36.6621 96.0839 36.6621C96.1046 36.6567 96.1176 36.6643 96.123 36.6849L96.1849 36.6687C96.2566 36.6058 96.2974 36.551 96.3072 36.5043C96.5203 36.1396 96.6959 35.8841 96.8339 35.7376C96.8491 35.7115 96.8644 35.6855 96.8796 35.6594C96.91 35.6073 96.9329 35.5683 96.9481 35.5422L97.6428 34.533L97.8092 34.1585L98.0081 33.9078C98.0287 33.9024 98.0418 33.91 98.0472 33.9306L98.0553 33.9616L97.9868 34.0788C97.9976 34.1201 97.9954 34.1537 97.9802 34.1798L98.104 34.1473L98.1416 34.0382L98.4694 33.5222L99.0189 32.7164L99.3614 32.1303C99.3919 32.0782 99.4017 32.0315 99.3909 31.9903C99.4115 31.9848 99.4191 31.9718 99.4137 31.9512C99.4083 31.9305 99.3953 31.9229 99.3746 31.9284C99.3638 31.8871 99.3432 31.8925 99.3127 31.9446L98.6495 32.317L97.763 32.8473C97.7272 32.8788 97.6577 32.908 97.5545 32.9351C97.5545 32.9351 97.5442 32.9378 97.5235 32.9432C97.5235 32.9432 97.5262 32.9535 97.5316 32.9741C97.4447 33.0631 97.3035 33.1553 97.1079 33.2507L97.0542 33.2979C96.8228 33.4247 96.5833 33.5206 96.3356 33.5856C96.2271 33.592 96.0593 33.625 95.8323 33.6845C95.7497 33.7062 95.6905 33.7327 95.6547 33.7642L95.5309 33.7967C95.4277 33.8237 95.2621 33.8231 95.0341 33.7946C94.9928 33.8055 94.9255 33.8011 94.8321 33.7814C94.7648 33.7771 94.627 33.714 94.4186 33.5922C94.4186 33.5922 94.3014 33.5237 94.0669 33.3867C94.0615 33.366 94.0382 33.3611 93.9969 33.372L93.9578 33.3491L93.9335 33.2563C93.9173 33.1944 93.8723 33.1069 93.7985 32.9939C93.7095 32.907 93.6147 32.7554 93.5139 32.5393C93.4597 32.3329 93.4881 32.1049 93.5991 31.8553L93.7737 31.5117C93.8139 31.413 93.9003 31.28 94.033 31.1129L94.0477 31.0429C94.0575 30.9962 94.0727 30.9701 94.0933 30.9647C94.1346 30.9539 94.1656 30.9458 94.1862 30.9404C94.2221 30.9089 94.2916 30.8796 94.3948 30.8526C94.4306 30.8211 94.4225 30.7902 94.3704 30.7597C94.3704 30.7597 94.3443 30.7445 94.2923 30.7141L94.4389 30.6425C94.4802 30.6317 94.4954 30.6056 94.4846 30.5644C94.4944 30.5177 94.4912 30.4634 94.4749 30.4015C94.4847 30.3548 94.5076 30.3157 94.5434 30.2843C94.5793 30.2528 94.6102 30.2447 94.6363 30.2599C94.6569 30.2545 94.6699 30.2621 94.6754 30.2827L94.7388 30.3984C94.7648 30.4137 94.7806 30.4316 94.786 30.4522C94.8066 30.4468 94.8142 30.4338 94.8088 30.4132C94.8132 30.3458 94.8415 30.3274 94.8936 30.3578L95.0255 30.3563L95.814 30.0833L96.1545 29.994C96.237 29.9724 96.3707 29.8932 96.5554 29.7566L96.9025 29.5663C97.0209 29.5132 97.1854 29.4259 97.3962 29.3044C97.6015 29.1624 97.7943 29.0567 97.9746 28.9873L99.1021 28.4931L99.5421 28.2784L100.106 28.0313L101.01 27.6949L101.264 27.529C101.285 27.5236 101.306 27.5182 101.326 27.5127C101.347 27.5073 101.352 27.484 101.341 27.4427L101.403 27.4265L101.696 27.2834L102.136 27.0687L102.336 26.95C102.429 26.8817 102.568 26.8232 102.754 26.7744C102.981 26.7149 103.148 26.6819 103.257 26.6755L103.529 26.7034C103.55 26.698 103.563 26.7056 103.568 26.7262C103.573 26.7469 103.586 26.7545 103.607 26.7491L103.771 26.8714L103.819 26.9252C103.829 26.9664 103.814 26.9925 103.773 27.0033L103.742 27.0114C103.727 27.0375 103.699 27.0559 103.657 27.0667L103.766 27.1043C103.695 27.1672 103.633 27.1834 103.581 27.153C103.529 27.1225 103.503 27.1073 103.503 27.1073L103.449 27.1545L103.496 27.2083C103.559 27.28 103.616 27.3311 103.668 27.3615L103.677 27.3925L103.615 27.4087L103.584 27.4168L103.623 27.4397L103.771 27.5001L103.802 27.4919L103.934 27.4904C103.934 27.4904 103.924 27.4931 103.903 27.4985C103.903 27.4985 103.906 27.5089 103.911 27.5295C103.89 27.5349 103.87 27.5403 103.849 27.5457C103.844 27.5251 103.833 27.5278 103.818 27.5539C103.756 27.5701 103.728 27.5885 103.733 27.6092C103.713 27.6146 103.705 27.6276 103.711 27.6482C103.737 27.6635 103.76 27.6684 103.781 27.663C103.843 27.6467 103.886 27.6462 103.913 27.6614C103.939 27.6767 103.942 27.7309 103.922 27.8243C103.907 27.8504 103.902 27.8737 103.907 27.8943C103.934 27.9096 103.957 27.9145 103.977 27.9091C104.05 27.9341 104.082 27.9699 104.072 28.0166C104.072 28.0166 104.077 28.0373 104.088 28.0785C104.099 28.1198 104.12 28.1144 104.15 28.0623L104.189 28.0851C104.236 28.0949 104.244 28.1259 104.213 28.178L104.191 28.2171L104.207 28.279C104.227 28.2736 104.264 28.2861 104.316 28.3165C104.363 28.3263 104.401 28.3052 104.432 28.2531L104.502 28.2678C104.544 28.3449 104.623 28.4346 104.738 28.5367C104.764 28.552 104.79 28.5672 104.816 28.5824C104.842 28.5976 104.858 28.6156 104.863 28.6362C104.879 28.6981 104.875 28.7654 104.85 28.8382C104.819 28.8902 104.796 28.9293 104.781 28.9554C104.766 28.9814 104.751 29.0075 104.736 29.0335C104.72 29.0596 104.705 29.0856 104.69 29.1117C104.559 29.4547 104.451 29.7146 104.365 29.8916C104.285 30.0891 104.214 30.24 104.153 30.3442L103.749 30.9465C103.601 31.1397 103.499 31.2547 103.442 31.2915C103.406 31.323 103.363 31.3675 103.312 31.425C103.276 31.4565 103.24 31.4879 103.204 31.5194C103.015 31.7234 102.788 31.9925 102.523 32.3267L102.255 32.6946L101.857 33.1959L101.796 33.2121C101.856 33.108 101.905 33.0401 101.941 33.0087C101.853 33.0097 101.778 33.0623 101.717 33.1665L101.419 33.5425L101.342 33.6287L101.334 33.5978C101.426 33.4415 101.507 33.3319 101.579 33.269L101.647 33.1518C101.668 33.1464 101.668 33.1464 101.647 33.1518C101.642 33.1311 101.647 33.1078 101.662 33.0817L101.654 33.0508L101.791 32.8164L101.76 32.8245L101.02 33.9119L100.835 34.0925L100.583 34.3904L100.384 34.6411L100.154 34.8998L99.9094 35.2286L99.6111 35.6046C99.6111 35.6046 99.573 35.6698 99.4969 35.8C99.4969 35.8 99.4866 35.8027 99.4659 35.8081C99.4659 35.8081 99.4632 35.7978 99.4578 35.7772L99.4269 35.7853C99.391 35.8168 99.3345 35.8536 99.2574 35.8959C99.2009 35.9328 99.1704 35.9849 99.1661 36.0522C99.1617 36.1195 99.1133 36.1873 99.0209 36.2557L98.8596 36.3972C98.8389 36.4027 98.8313 36.4157 98.8367 36.4363L98.6231 36.757L98.5921 36.7651C98.6378 36.687 98.6607 36.6479 98.6607 36.6479C98.5835 36.6902 98.5531 36.7423 98.5693 36.8042C98.5595 36.8509 98.5394 36.9003 98.5089 36.9524C98.4731 36.9838 98.4475 37.0126 98.4323 37.0386C98.3193 37.1124 98.2476 37.1753 98.2172 37.2274C98.1759 37.2382 98.158 37.2539 98.1634 37.2746C98.159 37.3419 98.1106 37.4097 98.0182 37.4781C98.0138 37.5454 97.9736 37.6442 97.8975 37.7744L97.6301 38.1423L97.2941 38.6274C97.2941 38.6274 97.2789 38.6534 97.2485 38.7055L97.18 38.8227L97.1653 38.8928L96.9973 39.1353L96.7608 39.4951L96.5015 39.8939C96.4809 39.8993 96.476 39.9227 96.4868 39.9639L96.5487 39.9477L96.6548 39.7214L96.7314 39.6351C96.7987 39.6395 96.8628 39.5896 96.9237 39.4854L97.5286 38.7644C97.5644 38.7329 97.6128 38.6651 97.6737 38.5609L97.9574 38.2549L97.9883 38.2468L97.729 38.6456C97.729 38.6456 97.6757 38.7368 97.5692 38.9191L97.4012 39.1617L97.0962 39.6387L96.8598 39.9984C96.763 40.1341 96.6793 40.2773 96.6086 40.4282L96.1225 41.3497L95.7211 42.2159L95.7226 42.3478C95.728 42.3684 95.7079 42.4178 95.6622 42.496C95.5861 42.6262 95.5481 42.6913 95.5481 42.6913C95.5329 42.7174 95.5513 42.7456 95.6034 42.7761C95.712 42.7696 95.8591 42.7421 96.0448 42.6934C96.0655 42.688 96.0861 42.6825 96.1068 42.6771C96.122 42.6511 96.1247 42.6614 96.1149 42.7081C96.0942 42.7135 96.0866 42.7265 96.092 42.7472C96.1127 42.7417 96.123 42.739 96.123 42.739L96.3087 42.6903C96.4782 42.5797 96.7536 42.4523 97.1348 42.3082L97.2586 42.2758L98.0456 41.8708C98.0663 41.8654 98.0918 41.8367 98.1223 41.7846L98.3455 41.6268C98.3607 41.6007 98.3993 41.5796 98.4612 41.5633L98.5231 41.5471C98.5546 41.583 98.5882 41.5852 98.6241 41.5537C98.66 41.5222 98.6985 41.5011 98.7398 41.4903L98.585 41.5309L98.546 41.508L98.6307 41.4527L99.2482 41.1584L99.7191 40.9357L100.175 40.7829C100.33 40.6984 100.469 40.6398 100.592 40.6074C100.649 40.5705 100.739 40.5358 100.863 40.5033C100.94 40.4611 101.051 40.421 101.195 40.3831L101.257 40.3668C101.272 40.3408 101.293 40.3354 101.319 40.3506C101.34 40.3452 101.358 40.3295 101.373 40.3034C101.409 40.272 101.478 40.2427 101.581 40.2156L101.567 40.2857L101.598 40.2775C101.613 40.2515 101.623 40.2488 101.629 40.2694C101.649 40.264 101.667 40.2483 101.682 40.2222L101.713 40.2141L101.643 40.1994C101.788 40.1615 101.888 40.1241 101.945 40.0873C102.001 40.0504 102.094 40.026 102.223 40.0142C102.347 39.9817 102.458 39.9416 102.556 39.8939C102.597 39.8831 102.618 39.8777 102.618 39.8777L102.671 39.8305L102.601 39.8158L102.517 39.8711C102.491 39.8559 102.457 39.8537 102.416 39.8645C102.431 39.8384 102.469 39.8173 102.531 39.8011L102.523 39.7701C102.255 39.8405 102.046 39.8843 101.896 39.9015L101.888 39.8706L102.166 39.7975L102.251 39.7422L102.336 39.6869L102.584 39.6219C102.584 39.6219 102.594 39.6192 102.614 39.6138C102.65 39.5824 102.674 39.5873 102.685 39.6285C102.685 39.6285 102.687 39.6389 102.693 39.6595C102.693 39.6595 102.703 39.6568 102.724 39.6514L103.103 39.5849L103.258 39.5443C103.495 39.4381 103.665 39.3715 103.768 39.3444L103.822 39.2972C103.831 39.2505 103.86 39.2321 103.906 39.2419C103.974 39.2463 104.028 39.2431 104.069 39.2323L104.472 39.1267L104.503 39.1186L104.573 39.1333L104.519 39.1805L104.426 39.2049C104.23 39.3002 104.081 39.3615 103.978 39.3885L103.986 39.4195L103.994 39.4504L104.025 39.4423L104.118 39.418C104.103 39.444 104.085 39.4597 104.064 39.4652C104.044 39.4706 104.033 39.4733 104.033 39.4733C103.961 39.4482 103.899 39.4645 103.848 39.522C103.853 39.5426 103.845 39.5557 103.825 39.5611L103.864 39.5839L103.895 39.5758C103.823 39.6387 103.756 39.6783 103.694 39.6945C103.632 39.7108 103.593 39.6879 103.577 39.626L103.546 39.6341L103.484 39.6504C103.464 39.6558 103.446 39.6715 103.43 39.6976C103.41 39.703 103.397 39.6954 103.391 39.6747C103.345 39.6649 103.327 39.6806 103.338 39.7219C103.322 39.748 103.284 39.7691 103.222 39.7853L102.96 39.9203C102.877 39.942 102.759 39.9951 102.604 40.0796C102.604 40.0796 102.582 40.1187 102.536 40.1969L102.575 40.2197L102.823 40.1547C102.905 40.1331 102.962 40.1402 102.994 40.1761L102.94 40.2232C102.827 40.297 102.729 40.3447 102.646 40.3663L102.33 40.5485L102.029 40.6606L102.006 40.6997C101.877 40.7116 101.789 40.7565 101.744 40.8347L101.814 40.8494C101.85 40.8179 101.901 40.8044 101.969 40.8088C102.051 40.7872 102.1 40.7633 102.115 40.7373C102.11 40.7166 102.12 40.7139 102.146 40.7291C102.167 40.7237 102.187 40.7183 102.208 40.7129L102.386 40.6332L102.417 40.6251C102.422 40.6458 102.414 40.6588 102.394 40.6642L102.131 40.7992L101.962 40.9098L102.302 40.8205L102.403 40.8271C102.429 40.8423 102.463 40.8445 102.504 40.8337C102.582 40.7914 102.703 40.7486 102.868 40.7053L102.876 40.7363L102.242 40.9687L102.381 40.8662L102.257 40.8986C102.133 40.9311 102.032 40.9685 101.955 41.0108C101.858 41.0585 101.644 41.1696 101.315 41.3441L101.284 41.3523C101.284 41.3523 101.287 41.3626 101.292 41.3832C101.292 41.3832 101.282 41.3859 101.261 41.3913L101.292 41.3832C101.395 41.3562 101.524 41.3003 101.678 41.2158L102.149 40.993L102.188 41.0158L102.126 41.0321C102.096 41.0842 102.081 41.1102 102.081 41.1102L102.143 41.094C102.204 41.0778 102.259 41.0745 102.305 41.0843L102.19 41.1478C102.128 41.164 102.074 41.2112 102.028 41.2893C102.013 41.3154 101.995 41.3311 101.975 41.3365C101.949 41.3213 101.928 41.3267 101.913 41.3528L101.828 41.4081L101.921 41.3837L102.177 41.3497C102.259 41.3281 102.318 41.3015 102.354 41.2701L102.563 41.1823L102.988 41.0377L103.135 40.9661L103.143 40.9971C103.107 41.0285 103.037 41.0578 102.934 41.0849L102.788 41.1564C102.618 41.267 102.466 41.3179 102.331 41.3091C102.331 41.3091 102.321 41.3118 102.3 41.3173C102.3 41.3173 102.303 41.3276 102.309 41.3482L101.992 41.5304L101.939 41.5776C101.98 41.5667 102.014 41.5689 102.04 41.5842L102.11 41.5989L102.056 41.6461C102.035 41.6515 102.017 41.6672 102.002 41.6933C102.002 41.6933 101.989 41.6856 101.963 41.6704L101.909 41.7176L101.956 41.7714L102.018 41.7552C102.152 41.676 102.384 41.5931 102.714 41.5065L102.722 41.5375C102.66 41.5537 102.465 41.6491 102.135 41.8237C101.801 41.9776 101.6 42.0523 101.533 42.0479L101.857 41.8967L101.95 41.8724C101.924 41.8572 101.903 41.8186 101.886 41.7567L101.785 41.7501L101.23 42.0282L101.199 42.0363C101.137 42.0525 101.083 42.0997 101.037 42.1778C101.043 42.1985 101.025 42.2142 100.984 42.225L100.899 42.2803L100.868 42.2885C100.847 42.2939 100.816 42.302 100.775 42.3128C100.754 42.3182 100.75 42.3416 100.76 42.3828C100.766 42.4035 100.758 42.4165 100.738 42.4219C100.711 42.4067 100.696 42.3888 100.69 42.3681L100.628 42.3844C100.65 42.4669 100.622 42.4853 100.544 42.4397L100.513 42.4478C100.441 42.5107 100.356 42.566 100.259 42.6137C100.181 42.656 100.104 42.6983 100.027 42.7406C99.9652 42.7568 99.9163 42.7807 99.8805 42.8121L99.8495 42.8202L99.8886 42.8431C99.9559 42.8475 100.021 42.8416 100.082 42.8253C100.139 42.7884 100.188 42.7646 100.229 42.7538L100.477 42.6888C100.477 42.6888 100.503 42.704 100.555 42.7345L100.563 42.7654L100.594 42.7573C100.614 42.664 100.657 42.6195 100.724 42.6239C100.807 42.6022 100.858 42.5887 100.879 42.5833C100.894 42.5572 100.923 42.5388 100.964 42.528C101.005 42.5171 101.039 42.5193 101.065 42.5346C101.095 42.4825 101.121 42.4537 101.141 42.4483C101.219 42.406 101.34 42.3632 101.505 42.3199C101.582 42.2776 101.713 42.2321 101.899 42.1834C101.956 42.1466 102.056 42.1092 102.2 42.0713L102.27 42.086L102.217 42.1332L102 42.19C101.979 42.1954 101.961 42.2112 101.946 42.2372C101.931 42.2633 101.91 42.2687 101.884 42.2535C101.869 42.2795 101.841 42.2979 101.8 42.3088C101.779 42.3142 101.761 42.3299 101.746 42.356C101.643 42.383 101.573 42.4123 101.537 42.4437L101.506 42.4519C101.46 42.442 101.4 42.4686 101.329 42.5315L101.298 42.5396C101.272 42.5244 101.241 42.5325 101.205 42.564C101.169 42.5955 101.141 42.6139 101.12 42.6193L101.027 42.6437L100.996 42.6518C100.986 42.6985 100.961 42.7272 100.92 42.738C100.894 42.7228 100.87 42.7179 100.85 42.7233C100.814 42.7548 100.755 42.7813 100.672 42.803L100.641 42.8111C100.631 42.8578 100.595 42.8893 100.534 42.9055C100.487 42.8957 100.443 42.8962 100.402 42.907L100.024 43.1054C100.024 43.1054 100.008 43.1315 99.9779 43.1836L100.079 43.1902L100.195 43.1267L100.256 43.1105L100.234 43.1496L99.9485 43.3236C99.7888 43.3875 99.6269 43.4851 99.4629 43.6164L99.3081 43.657L98.9301 43.8554L98.8991 43.8635C98.9099 43.9048 98.8947 43.9308 98.8534 43.9416C98.8274 43.9264 98.8144 43.9188 98.8144 43.9188C98.7839 43.9709 98.7584 43.9997 98.7377 44.0051L98.7068 44.0132C98.6547 43.9827 98.6341 43.9882 98.6449 44.0294C98.6351 44.0761 98.6019 44.1179 98.5454 44.1548C98.5042 44.1656 98.4656 44.1867 98.4297 44.2182L98.1136 44.4004L98.0908 44.4394L98.1299 44.4623C98.1863 44.4254 98.2483 44.4092 98.3156 44.4135C98.3775 44.3973 98.4367 44.3708 98.4932 44.3339C98.5703 44.2916 98.6681 44.2439 98.7865 44.1908C98.9049 44.1377 98.995 44.103 99.0569 44.0868C99.2883 43.9599 99.4942 43.8618 99.6745 43.7925C99.8548 43.7231 100.004 43.6619 100.123 43.6088C100.318 43.5134 100.478 43.4494 100.602 43.417L100.124 43.7407L99.3599 44.1066C99.2827 44.1488 99.1209 44.2464 98.8742 44.3993L98.4653 44.6059L98.3952 44.5911C98.2768 44.6443 98.1562 44.731 98.0334 44.8515C97.9769 44.8883 97.9205 44.9252 97.864 44.9621C97.8075 44.9989 97.751 45.0358 97.6945 45.0727C97.638 45.1096 97.5658 45.1285 97.4778 45.1295C97.4616 45.0676 97.4279 45.0654 97.3768 45.1229C97.2845 45.1913 97.241 45.2357 97.2464 45.2564C97.2366 45.3031 97.2008 45.3345 97.1388 45.3508L97.046 45.3751C96.9743 45.438 96.7972 45.5617 96.5147 45.746C96.4789 45.7775 96.4403 45.7986 96.399 45.8095C96.3784 45.8149 96.3496 45.7893 96.3128 45.7328C96.2975 45.7589 96.2693 45.7773 96.228 45.7882C96.1867 45.799 96.1585 45.8174 96.1433 45.8435C96.1335 45.8901 96.1003 45.9319 96.0438 45.9688C95.9873 46.0057 95.9488 46.0268 95.9281 46.0322L95.2649 46.4047C95.203 46.4209 95.1541 46.4448 95.1183 46.4762C95.1031 46.5023 95.0775 46.531 95.0417 46.5625L94.9178 46.595L94.6393 46.668ZM94.9478 43.8082C94.8652 43.8298 94.806 43.8564 94.7702 43.8878L94.7783 43.9188L94.9478 43.8082ZM94.1699 42.9867L94.245 42.7685L94.2059 42.7456C94.2059 42.7456 94.2086 42.7559 94.2141 42.7766C94.2141 42.7766 94.2037 42.7793 94.1831 42.7847L94.1308 42.9638L94.139 42.9948L94.1699 42.9867ZM97.9634 44.8367L97.9325 44.8449L97.6082 44.9961L97.6163 45.027L97.9634 44.8367ZM95.5344 43.522C95.5344 43.522 95.5496 43.4959 95.58 43.4438L95.5181 43.4601L95.4643 43.5073L95.5344 43.522ZM94.6413 42.1352C94.5381 42.1623 94.4898 42.2301 94.4962 42.3387L94.6413 42.1352ZM94.6332 42.1042C94.6636 42.0521 94.6762 42.0158 94.6707 41.9951L94.6398 42.0033L94.586 42.0505L94.6332 42.1042ZM94.3922 42.0682C94.3813 42.0269 94.3656 42.009 94.345 42.0144C94.3396 41.9938 94.3369 41.9835 94.3369 41.9835C94.3575 41.9781 94.3678 41.9754 94.3678 41.9754L94.4363 41.8581C94.4668 41.806 94.482 41.78 94.482 41.78L94.5342 41.6009C94.5288 41.5802 94.5364 41.5672 94.5571 41.5618L94.619 41.5456L94.6043 41.6156L94.5601 41.8257L94.4688 41.9819C94.4383 42.034 94.4128 42.0628 94.3922 42.0682ZM98.5505 43.9219C98.5505 43.9219 98.5657 43.8958 98.5962 43.8437L98.4952 43.8371L98.4724 43.8762C98.4724 43.8762 98.4984 43.8914 98.5505 43.9219ZM98.4399 43.7524C98.5018 43.7361 98.5404 43.715 98.5556 43.6889C98.5762 43.6835 98.5838 43.6705 98.5784 43.6499L98.5475 43.658L98.4318 43.7214L98.4399 43.7524ZM98.6616 43.4626L98.6535 43.4317L98.2445 43.6382L98.2527 43.6692L98.6616 43.4626ZM98.2283 43.5763C98.3108 43.5546 98.37 43.5281 98.4059 43.4966L98.3978 43.4657C98.3619 43.4971 98.3027 43.5237 98.2202 43.5453L98.2283 43.5763ZM94.6484 41.4055L94.7398 41.2492C94.756 41.3111 94.7489 41.3681 94.7184 41.4202L94.6875 41.4283L94.6484 41.4055ZM98.7332 43.6093C98.7951 43.593 98.8337 43.5719 98.8489 43.5459C98.8695 43.5404 98.8771 43.5274 98.8717 43.5068L98.8408 43.5149C98.7789 43.5311 98.7403 43.5523 98.7251 43.5783L98.7022 43.6174L98.7332 43.6093ZM97.5484 42.4975C97.5484 42.4975 97.5429 42.4769 97.5321 42.4356L97.4636 42.5528L97.5336 42.5675L97.5484 42.4975ZM99.3375 43.5169L99.3456 43.5479L99.4842 43.4454L99.507 43.4063L99.4451 43.4226C99.4451 43.4226 99.4375 43.4356 99.4223 43.4616C99.4016 43.467 99.3756 43.4518 99.3441 43.416L99.3132 43.4241L99.2284 43.4794C99.1872 43.4902 99.1746 43.5266 99.1909 43.5885C99.1963 43.6091 99.199 43.6194 99.199 43.6194C99.2196 43.614 99.23 43.6113 99.23 43.6113L99.3375 43.5169ZM95.8262 41.2289L95.818 41.198L95.7937 41.1051C95.7632 41.1572 95.748 41.1833 95.748 41.1833L95.611 41.4177L95.5963 41.4877C95.6484 41.5182 95.6793 41.51 95.6891 41.4634L95.8262 41.2289ZM98.893 43.3358C98.9137 43.3304 98.924 43.3277 98.924 43.3277C98.9186 43.307 98.9159 43.2967 98.9159 43.2967L99.3558 43.0821C99.4275 43.0191 99.4845 43.0263 99.5268 43.1034L99.5024 43.0105C99.5491 43.0203 99.5828 43.0225 99.6034 43.0171C99.6393 42.9857 99.6545 42.9596 99.6491 42.939C99.6437 42.9183 99.6307 42.9107 99.61 42.9161L99.3705 43.012L98.8996 43.2348L98.5216 43.4332L98.5297 43.4642C98.5449 43.4381 98.5835 43.417 98.6454 43.4007C98.7279 43.3791 98.7822 43.3759 98.8083 43.3911L98.893 43.3358ZM95.3233 40.6992C95.3385 40.6731 95.3668 40.6547 95.408 40.6439C95.4395 40.6797 95.4373 40.7134 95.4014 40.7449C95.3808 40.7503 95.3629 40.766 95.3477 40.792L95.3233 40.6992ZM99.6618 43.3657C99.6824 43.3603 99.69 43.3473 99.6846 43.3266C99.7151 43.2746 99.746 43.2664 99.7775 43.3023C99.8708 43.3219 99.9067 43.2905 99.885 43.2079C99.9057 43.2025 99.9133 43.1895 99.9079 43.1688L99.8769 43.177C99.7737 43.204 99.7042 43.2333 99.6684 43.2647L99.6455 43.3038L99.6618 43.3657ZM94.9833 42.1778C94.9779 42.1572 94.9855 42.1442 95.0062 42.1387C95.0366 42.0867 95.0491 42.0503 95.0437 42.0297C95.0948 41.9721 95.1225 41.9097 95.1269 41.8424C95.152 41.7697 95.19 41.7046 95.2411 41.6471C95.3585 41.506 95.4194 41.4018 95.4238 41.3345C95.4184 41.3138 95.4156 41.3035 95.4156 41.3035C95.4363 41.2981 95.4466 41.2954 95.4466 41.2954L95.4841 41.1863L95.476 41.1554C95.5674 40.9991 95.6152 40.8873 95.6196 40.82C95.6609 40.8091 95.6864 40.7804 95.6963 40.7337C95.7061 40.687 95.7289 40.6479 95.7648 40.6165C95.7648 40.6165 95.8028 40.5514 95.8789 40.4211L96.0078 40.1557L96.1824 39.8122L96.3356 39.6397L96.5264 39.3581C96.5873 39.2539 96.6357 39.186 96.6715 39.1546L96.7172 39.0764L96.7548 38.9673L96.67 39.0227L96.6015 39.1399L96.4335 39.3824C96.3727 39.4866 96.3113 39.5468 96.2494 39.5631C96.2754 39.5783 96.2911 39.5962 96.2965 39.6168C96.2965 39.6168 96.2862 39.6196 96.2656 39.625L96.1971 39.7422L95.915 40.1801L95.5039 40.8834C95.4887 40.9094 95.3979 41.1097 95.2314 41.4842C95.2467 41.4581 95.1254 41.7105 94.8676 42.2412L94.8154 42.4204L94.8544 42.4432L94.9833 42.1778ZM95.3659 40.3572C95.3605 40.3365 95.3475 40.3289 95.3269 40.3343C95.3214 40.3137 95.3263 40.2904 95.3416 40.2643C95.3362 40.2437 95.3487 40.2073 95.3791 40.1552L95.3872 40.1862L95.3954 40.2171C95.3649 40.2692 95.3627 40.3029 95.3888 40.3181C95.4148 40.3333 95.4175 40.3436 95.3969 40.3491L95.3659 40.3572ZM98.5896 41.9267C98.5744 41.9527 98.5461 41.9711 98.5048 41.982L98.4511 42.0292L98.5211 42.0439L98.5896 41.9267ZM98.448 41.7653L98.378 41.7506L98.3242 41.7978C98.3296 41.8184 98.3323 41.8287 98.3323 41.8287C98.353 41.8233 98.3633 41.8206 98.3633 41.8206L98.448 41.7653ZM95.7181 39.934C95.7127 39.9134 95.6996 39.9057 95.679 39.9112C95.679 39.9112 95.7323 39.82 95.8388 39.6377L95.8698 39.6295C95.8752 39.6502 95.8676 39.6632 95.847 39.6686C95.8524 39.6892 95.8399 39.7256 95.8094 39.7777L95.7181 39.934ZM95.9647 39.1084L95.9256 39.0856C95.9104 39.1116 95.8821 39.1301 95.8409 39.1409C95.8202 39.1463 95.8023 39.162 95.7871 39.1881C95.7665 39.1935 95.7588 39.2065 95.7643 39.2271C95.7697 39.2478 95.7648 39.2711 95.7495 39.2972C95.7702 39.2918 95.7832 39.2994 95.7886 39.32C95.8092 39.3146 95.8272 39.2989 95.8424 39.2728L95.9647 39.1084ZM100.838 42.4285L100.985 42.357L101.371 42.1895L101.386 42.1195C101.407 42.1141 101.417 42.1114 101.417 42.1114C101.412 42.0907 101.409 42.0804 101.409 42.0804L101.471 42.0642C101.461 42.1109 101.466 42.1315 101.487 42.1261C101.528 42.1153 101.549 42.1099 101.549 42.1099C101.626 42.0676 101.737 42.0275 101.881 41.9896C101.896 41.9635 101.907 41.9608 101.912 41.9815C101.933 41.9761 101.943 41.9734 101.943 41.9734C101.871 42.0363 101.774 42.084 101.65 42.1164C101.547 42.1435 101.464 42.1652 101.402 42.1814C101.31 42.2497 101.125 42.3424 100.847 42.4595L100.838 42.4285ZM97.796 42.4326L98.3207 42.1626L98.3354 42.0926C98.3875 42.123 98.4108 42.1279 98.4054 42.1073C98.4879 42.0857 98.5471 42.0591 98.583 42.0276C98.6449 42.0114 98.6471 41.9777 98.5896 41.9267C98.6928 41.8996 98.7726 41.8676 98.8291 41.8308L98.86 41.8226C98.8905 41.7705 98.9264 41.7391 98.9676 41.7283C98.9839 41.7902 99.0072 41.7951 99.0376 41.743C99.0583 41.7376 99.0789 41.7321 99.0996 41.7267C99.1408 41.7159 99.1533 41.6795 99.1371 41.6176C99.1425 41.6383 99.1479 41.6589 99.1533 41.6795C99.174 41.6741 99.187 41.6817 99.1924 41.7024L99.2234 41.6943L99.2462 41.6552C99.2039 41.5781 99.2295 41.5493 99.3228 41.5689C99.3847 41.5527 99.4928 41.5023 99.6471 41.4177C99.6677 41.4123 99.6987 41.4042 99.7399 41.3934C99.7964 41.3565 99.8377 41.3457 99.8637 41.3609C99.8898 41.3761 99.9028 41.3837 99.9028 41.3837C99.918 41.3577 99.936 41.3419 99.9566 41.3365L99.9094 41.2827C99.9453 41.2513 100.004 41.2247 100.087 41.2031C100.102 41.177 100.113 41.1743 100.118 41.195C100.139 41.1895 100.141 41.1999 100.126 41.2259L100.142 41.2878L100.188 41.2097L100.18 41.1787L100.234 41.1315C100.26 41.1468 100.28 41.1413 100.296 41.1153C100.29 41.0947 100.308 41.0789 100.349 41.0681L100.944 40.8129L100.975 40.8048C100.985 40.7581 101 40.732 101.021 40.7266C101.041 40.7212 101.059 40.7055 101.074 40.6794L101.376 40.5673C101.587 40.4458 101.775 40.3635 101.94 40.3202C102.043 40.2931 102.099 40.2562 102.109 40.2095L102.14 40.2014C102.218 40.2471 102.249 40.239 102.233 40.1771C102.248 40.151 102.276 40.1326 102.318 40.1218L102.38 40.1055L102.371 40.0746L102.279 40.0989C102.237 40.1098 102.188 40.1336 102.132 40.1705C102.075 40.2073 102.024 40.2209 101.977 40.2111C101.853 40.2435 101.652 40.3183 101.374 40.4353L100.98 40.5718L100.617 40.7002C100.596 40.7056 100.565 40.7138 100.524 40.7246C100.498 40.7094 100.47 40.7278 100.439 40.7799L100.377 40.7961L100.192 40.8448L100.161 40.853C100.171 40.8942 100.156 40.9203 100.115 40.9311C100.089 40.9159 100.076 40.9083 100.076 40.9083C99.9933 40.9299 99.9444 40.9538 99.9292 40.9798C99.8933 41.0113 99.8341 41.0378 99.7516 41.0595L99.7206 41.0676L99.2498 41.2903C99.1259 41.3228 99.0515 41.3754 99.0265 41.4482C98.9852 41.459 98.957 41.4774 98.9417 41.5035C98.8798 41.5197 98.8413 41.5408 98.8261 41.5669C98.7956 41.619 98.7391 41.6559 98.6566 41.6775L98.5947 41.6937C98.5947 41.6937 98.5843 41.6965 98.5637 41.7019C98.5637 41.7019 98.5664 41.7122 98.5718 41.7328L98.6028 41.7247L98.6109 41.7557L98.5033 41.85C98.4827 41.8554 98.4311 41.869 98.3486 41.8906C98.2867 41.9069 98.2405 41.941 98.21 41.9931L98.1791 42.0012C98.1584 42.0067 98.1302 42.0251 98.0943 42.0566C98.0585 42.088 98.0433 42.1141 98.0487 42.1347C98.0335 42.1607 98.0258 42.1738 98.0258 42.1738C98.0204 42.1531 98.0074 42.1455 97.9868 42.1509L97.9477 42.1281L97.8939 42.1753L97.8777 42.1134L97.832 42.1915C97.8222 42.2382 97.82 42.2719 97.8254 42.2925C97.8308 42.3131 97.8438 42.3208 97.8645 42.3153L97.695 42.426L97.7031 42.4569L97.796 42.4326ZM96.1778 39.4164C96.3605 39.1038 96.4518 38.9476 96.4518 38.9476L96.5513 38.8222L96.5822 38.8141C96.592 38.7674 96.61 38.7517 96.636 38.7669C96.6621 38.7821 96.6724 38.7794 96.667 38.7588L96.6523 38.8288L96.2854 39.322L96.1778 39.4164ZM95.9977 38.6035L95.9277 38.5888C95.9277 38.5888 95.9124 38.6148 95.882 38.6669L95.9211 38.6898L95.9977 38.6035ZM96.0104 39.0303C96.031 39.0248 96.0386 39.0118 96.0332 38.9912L96.017 38.9293C96.0061 38.888 96.0317 38.8593 96.0936 38.843L96.1474 38.7958C96.1474 38.7958 96.1854 38.7307 96.2615 38.6005L96.2763 38.5304C96.2654 38.4892 96.2421 38.4843 96.2062 38.5157C96.1856 38.5211 96.1753 38.5239 96.1753 38.5239C96.2328 38.5749 96.2154 38.6346 96.123 38.703C96.0046 38.7561 95.954 38.8576 95.9713 39.0074C95.9919 39.002 96.0049 39.0096 96.0104 39.0303ZM96.8603 39.3697L97.3576 38.7431L97.1439 39.0638L97.0754 39.181C96.9733 39.296 96.8994 39.3926 96.8537 39.4707L96.7314 39.6351L96.8603 39.3697ZM102.324 42.0388L102.378 41.9916L102.533 41.951C102.502 42.0031 102.477 42.0319 102.456 42.0373L102.363 42.0616L102.332 42.0698L102.324 42.0388ZM96.4818 38.1788L96.4736 38.1479L96.4117 38.1641L96.3432 38.2813L96.3823 38.3041L96.4818 38.1788ZM96.5371 38.2635L96.498 38.2407C96.4774 38.2461 96.4698 38.2591 96.4752 38.2798L96.5224 38.3336L96.5371 38.2635ZM96.8314 38.8811C96.964 38.714 97.0607 38.5783 97.1216 38.4741C97.2238 38.3591 97.2977 38.2625 97.3434 38.1844C97.338 38.1638 97.3456 38.1507 97.3662 38.1453L97.3043 38.1616C97.2837 38.167 97.2761 38.18 97.2815 38.2006L96.9831 38.5766L96.7695 38.8973C96.7695 38.8973 96.7722 38.9076 96.7776 38.9283C96.7776 38.9283 96.7673 38.931 96.7466 38.9364L96.7776 38.9283L96.8314 38.8811ZM97.1475 38.6989C97.1834 38.6675 97.2317 38.5996 97.2926 38.4954L97.2845 38.4645L97.2536 38.4726C97.2536 38.4726 97.2231 38.5247 97.1622 38.6289L97.1313 38.637C97.1313 38.637 97.1209 38.6397 97.1003 38.6451C97.1003 38.6451 97.103 38.6554 97.1084 38.6761C97.0878 38.6815 97.0802 38.6945 97.0856 38.7152L97.1475 38.6989ZM102.696 41.9414C102.696 41.9414 102.685 41.9441 102.665 41.9495C102.665 41.9495 102.662 41.9392 102.657 41.9186L102.741 41.8632C102.762 41.8578 102.783 41.8524 102.803 41.847C102.818 41.821 102.839 41.8155 102.865 41.8308L102.904 41.8536L102.881 41.8927L102.696 41.9414ZM96.0433 38.5254C96.0433 38.5254 96.1042 38.4212 96.226 38.2128C96.2663 38.114 96.3119 38.0359 96.363 37.9784C96.4293 37.8948 96.4777 37.827 96.5081 37.7749L96.7903 37.337L96.8897 37.2117L96.9045 37.1416L96.8963 37.1107L96.8197 37.1969C96.7893 37.249 96.774 37.2751 96.774 37.2751C96.7588 37.3011 96.7153 37.3456 96.6436 37.4085L96.3387 37.8855L95.9962 38.4716C95.9755 38.477 95.9679 38.49 95.9733 38.5107C95.9733 38.5107 95.9787 38.5313 95.9896 38.5726L96.0433 38.5254ZM101.27 40.7936C101.579 40.7124 101.798 40.6219 101.926 40.5221L101.98 40.4749C101.954 40.4597 101.921 40.4575 101.879 40.4683C101.797 40.49 101.699 40.5377 101.586 40.6114C101.441 40.6493 101.341 40.6867 101.285 40.7236C101.264 40.729 101.233 40.7371 101.192 40.7479C101.171 40.7533 101.137 40.7511 101.091 40.7413L101.06 40.7494C101.091 40.7853 101.089 40.819 101.053 40.8504C101.033 40.8558 101.012 40.8612 100.991 40.8667L101.27 40.7936ZM102.901 41.5897L103.172 41.4857L103.18 41.5167C103.056 41.5492 102.966 41.5838 102.909 41.6207L102.901 41.5897ZM96.6203 38.0763C96.6193 37.9884 96.6627 37.9439 96.7507 37.9429C96.7507 37.9429 96.7355 37.9689 96.705 38.021L96.7588 37.9738C96.8458 37.8848 96.9066 37.7806 96.9415 37.6612C96.9621 37.6558 96.9724 37.6531 96.9724 37.6531C96.967 37.6325 96.9643 37.6222 96.9643 37.6222L96.9024 37.6384L96.8715 37.6465C96.8454 37.6313 96.8172 37.6497 96.7867 37.7018L96.7263 37.85L96.6954 37.8581C96.6693 37.8429 96.646 37.838 96.6254 37.8434C96.6254 37.8434 96.6281 37.8537 96.6335 37.8743C96.577 37.9112 96.5596 37.9709 96.5812 38.0535L96.5975 38.1154L96.6203 38.0763ZM100.829 40.2476C100.859 40.1955 100.975 40.1321 101.176 40.0573C101.371 39.9619 101.516 39.924 101.609 39.9437C101.522 40.0326 101.396 40.0988 101.231 40.1421C101.066 40.1854 100.932 40.2205 100.829 40.2476ZM94.5855 42.6792C94.6061 42.6737 94.6137 42.6607 94.6083 42.6401L94.8057 42.2575C94.8612 42.1327 94.8933 42.0029 94.9021 41.8683C94.9316 41.7282 94.974 41.5958 95.0295 41.471C95.0599 41.4189 95.1127 41.2837 95.1878 41.0655L95.2335 40.9874C95.2443 41.0287 95.2421 41.0623 95.2269 41.0884L95.1061 41.3847C95.1169 41.426 95.112 41.4493 95.0914 41.4547C95.1327 41.4439 95.1506 41.4282 95.1452 41.4075C95.181 41.3761 95.2088 41.3137 95.2284 41.2203L95.442 40.8996L95.8368 40.1344L96.1499 39.6884C96.3326 39.3758 96.4674 39.175 96.5543 39.0861L96.8136 38.6872L96.9669 38.5147C96.9919 38.442 97.0555 38.3481 97.1577 38.2331C97.1729 38.2071 97.206 38.1653 97.2571 38.1078C97.3028 38.0296 97.3148 37.9493 97.2931 37.8667L97.3241 37.8586L97.4758 37.5542C97.491 37.5281 97.5013 37.5254 97.5068 37.546C97.5274 37.5406 97.5453 37.5249 97.5605 37.4989C97.5812 37.4934 97.5888 37.4804 97.5834 37.4598L97.5753 37.4288L97.9421 36.9356C98.0139 36.8727 98.0546 36.8179 98.0644 36.7712C98.2177 36.5987 98.2943 36.5124 98.2943 36.5124C98.3095 36.4864 98.322 36.45 98.3318 36.4033C98.3417 36.3566 98.3802 36.3355 98.4475 36.3399L98.4394 36.3089C98.4699 36.2569 98.4954 36.2281 98.516 36.2227C98.5769 36.1185 98.6074 36.0664 98.6074 36.0664L98.852 35.7376C99.1879 35.2525 99.3482 35.023 99.333 35.049C99.3276 35.0284 99.3249 35.0181 99.3249 35.0181C99.3455 35.0127 99.3558 35.0099 99.3558 35.0099C99.3765 35.0045 99.4096 34.9628 99.4553 34.8846C99.4597 34.8173 99.4901 34.7652 99.5466 34.7283L99.6004 34.6811C99.595 34.6605 99.6026 34.6475 99.6232 34.6421C99.6385 34.616 99.6461 34.603 99.6461 34.603C99.6721 34.6182 99.6852 34.6258 99.6852 34.6258C99.7058 34.6204 99.7134 34.6074 99.708 34.5868L99.7227 34.5167L99.7699 34.5705C99.7905 34.5651 99.7981 34.5521 99.7927 34.5314C99.8232 34.4793 99.8384 34.4533 99.8384 34.4533C99.8732 34.3339 99.9113 34.2688 99.9526 34.2579C100.014 34.2417 100.027 34.2053 99.9901 34.1488C99.9793 34.1076 99.9815 34.0739 99.9967 34.0479C100.012 34.0218 100.017 33.9985 100.011 33.9778C100.016 33.9105 100.064 33.8427 100.157 33.7744C100.151 33.7537 100.159 33.7407 100.179 33.7353C100.185 33.7559 100.177 33.769 100.157 33.7744L100.165 33.8053C100.17 33.826 100.193 33.8309 100.235 33.82L100.189 33.8982L100.158 33.9063L100.166 33.9373L100.29 33.9048L100.266 33.8119C100.281 33.7859 100.283 33.7522 100.272 33.7109L100.287 33.6409L100.279 33.61C100.299 33.6045 100.313 33.6122 100.318 33.6328C100.339 33.6274 100.352 33.635 100.357 33.6556L100.395 33.5465L100.325 33.5318C100.325 33.5318 100.363 33.4667 100.439 33.3365L100.463 33.4293L100.448 33.4993L100.425 33.5384L100.487 33.5222L100.572 33.4669C100.567 33.4462 100.564 33.4359 100.564 33.4359C100.585 33.4305 100.595 33.4278 100.595 33.4278L100.556 33.405C100.494 33.4212 100.478 33.4033 100.509 33.3512L100.608 33.2258C100.639 33.1737 100.659 33.1683 100.67 33.2096L100.732 33.1934L100.724 33.1624C100.718 33.1418 100.705 33.1342 100.685 33.1396C100.679 33.1189 100.684 33.0956 100.7 33.0696C100.7 33.0696 100.71 33.0669 100.73 33.0614C100.746 33.0354 100.766 33.03 100.792 33.0452C100.798 33.0658 100.821 33.0707 100.862 33.0599L100.877 32.9899L100.869 32.9589L100.714 32.9995C100.694 33.0049 100.676 33.0207 100.66 33.0467C100.645 33.0728 100.622 33.0679 100.59 33.032L100.559 33.0401C100.508 33.0976 100.439 33.1709 100.352 33.2598C100.286 33.3434 100.24 33.4215 100.215 33.4943L100.224 33.5252L100.124 33.6506L100.062 33.6668C100.051 33.6255 100.038 33.6179 100.023 33.644C100.002 33.6494 99.9949 33.6624 100 33.683L99.7329 34.0509C99.6567 34.1812 99.6187 34.2463 99.6187 34.2463L99.5502 34.3635L99.4898 34.5117C99.3974 34.58 99.3387 34.6505 99.3137 34.7232C99.3137 34.7232 99.3034 34.726 99.2828 34.7314C99.2828 34.7314 99.2855 34.7417 99.2909 34.7623C99.2811 34.809 99.2506 34.8611 99.1995 34.9186C99.1431 34.9555 99.1099 34.9973 99.1001 35.0439L99.0854 35.114C99.1016 35.1759 99.0945 35.2329 99.0641 35.285L98.72 35.7391C98.5972 35.8595 98.4902 35.9979 98.3988 36.1542C98.2358 36.3734 98.1005 36.5302 97.9929 36.6246C98.0494 36.5877 98.0798 36.5356 98.0842 36.4683C98.0788 36.4476 98.0864 36.4346 98.1071 36.4292C98.1071 36.4292 98.0967 36.4319 98.0761 36.4373C98.0707 36.4167 98.0707 36.4167 98.0761 36.4373L98.0223 36.4845L97.9995 36.5236L97.8772 36.688L97.8853 36.7189L97.9929 36.6246L97.7026 37.0315C97.6668 37.063 97.6336 37.1048 97.6032 37.1569C97.5934 37.2035 97.5705 37.2426 97.5347 37.2741C97.514 37.2795 97.4809 37.3213 97.4352 37.3994C97.3895 37.4775 97.3156 37.5741 97.2135 37.6891L97.1597 37.7363L97.1516 37.7054L97.3195 37.4628C97.3706 37.4053 97.4087 37.3402 97.4337 37.2675C97.5359 37.1525 97.6152 37.0765 97.6717 37.0396L97.6636 37.0087L97.6017 37.0249L97.4646 37.2594C97.3517 37.3331 97.2876 37.383 97.2723 37.409L97.0815 37.6907C96.9794 37.8057 96.9364 37.8941 96.9527 37.956C96.9222 38.0081 96.8967 38.0369 96.876 38.0423C96.85 38.0271 96.8293 38.0325 96.8141 38.0585C96.8141 38.0585 96.8168 38.0689 96.8222 38.0895L96.8075 38.1595C96.7717 38.191 96.7233 38.2588 96.6624 38.363C96.6624 38.363 96.6396 38.4021 96.5939 38.4802C96.5939 38.4802 96.5966 38.4905 96.602 38.5112C96.602 38.5112 96.5917 38.5139 96.5711 38.5193C96.5657 38.4987 96.5477 38.5144 96.5173 38.5665L96.3803 38.8009C96.3444 38.8324 96.2656 38.9523 96.1438 39.1607L96.1519 39.1916C96.178 39.2068 96.1807 39.2172 96.16 39.2226C96.1394 39.228 96.1318 39.241 96.1372 39.2616C96.1112 39.2464 96.0905 39.2518 96.0753 39.2779C96.0753 39.2779 96.078 39.2882 96.0834 39.3088L95.9464 39.5433C95.9518 39.5639 95.9442 39.5769 95.9236 39.5823C95.9182 39.5617 95.9079 39.5644 95.8926 39.5905L95.8764 39.5286L95.8911 39.4585C95.8498 39.4694 95.8216 39.4878 95.8064 39.5138L95.7835 39.5529C95.7477 39.5844 95.7145 39.6261 95.6841 39.6782C95.6743 39.7249 95.6487 39.7537 95.6075 39.7645L95.6156 39.7955L95.6399 39.8883L95.578 39.9046C95.5574 39.91 95.5525 39.9333 95.5633 39.9746L95.5796 40.0365L95.5095 40.0218L95.4557 40.069C95.4557 40.069 95.4584 40.0793 95.4639 40.0999C95.4639 40.0999 95.4535 40.1026 95.4329 40.108L95.4167 40.0461C95.3656 40.1036 95.315 40.2051 95.2649 40.3506L95.0153 40.9123C94.9903 40.985 94.9598 41.0371 94.924 41.0686C94.8881 41.1 94.8626 41.1288 94.8473 41.1548C94.8169 41.2069 94.8017 41.233 94.8017 41.233C94.7962 41.2124 94.7805 41.1944 94.7545 41.1792C94.7491 41.1586 94.7567 41.1455 94.7773 41.1401L94.8981 40.8438C94.9187 40.8384 94.929 40.8357 94.929 40.8357C94.9236 40.815 94.9209 40.8047 94.9209 40.8047C94.9676 40.8145 94.9828 40.7885 94.9666 40.7266C95.0078 40.7158 95.0231 40.6897 95.0122 40.6484C95.0329 40.643 95.0432 40.6403 95.0432 40.6403C95.0378 40.6197 95.0351 40.6094 95.0351 40.6094C95.0188 40.5475 95.0183 40.5035 95.0336 40.4774L95.0483 40.4074C95.0429 40.3868 95.0402 40.3765 95.0402 40.3765C95.1075 40.3809 95.146 40.3597 95.1558 40.313C95.1504 40.2924 95.1477 40.2821 95.1477 40.2821C95.1684 40.2767 95.1787 40.274 95.1787 40.274L95.301 40.1096C95.3162 40.0835 95.3157 40.0395 95.2995 39.9776C95.2886 39.9364 95.2984 39.8897 95.3289 39.8376L95.3451 39.8995C95.3864 39.8887 95.4043 39.8729 95.3989 39.8523L95.4299 39.8442C95.4244 39.8235 95.4266 39.7899 95.4365 39.7432C95.4409 39.6759 95.4637 39.6368 95.505 39.626C95.5202 39.5999 95.5354 39.5739 95.5506 39.5478C95.5604 39.5012 95.5833 39.4621 95.6191 39.4306C95.6191 39.4306 95.6344 39.4046 95.6648 39.3525L95.681 39.4144L95.6892 39.4453C95.7304 39.4345 95.7456 39.4085 95.7348 39.3672C95.75 39.3411 95.7343 39.3232 95.6876 39.3134C95.6616 39.2982 95.6459 39.2803 95.6404 39.2596L95.6323 39.2287C95.678 39.1505 95.7008 39.1114 95.7008 39.1114L95.7775 39.0252L95.8084 39.0171L95.784 38.9242C95.7221 38.9404 95.6939 38.9589 95.6993 38.9795C95.6384 39.0837 95.5498 39.2503 95.4334 39.4793C95.4128 39.4847 95.4052 39.4978 95.4106 39.5184L95.4415 39.5103L95.5116 39.525L95.4578 39.5722C95.334 39.6047 95.2726 39.6649 95.2736 39.7528C95.279 39.7735 95.2714 39.7865 95.2507 39.7919C95.2507 39.7919 95.2328 39.8076 95.197 39.8391C95.1817 39.8651 95.1898 39.8961 95.2213 39.932L95.1904 39.9401L95.1366 39.9873L95.2147 40.0329L95.1609 40.0801C95.0882 40.0551 95.0599 40.0735 95.0762 40.1354L94.9473 40.4008C94.9321 40.4269 94.9092 40.4659 94.8788 40.518C94.8429 40.5495 94.8407 40.5831 94.8722 40.619C94.8776 40.6396 94.87 40.6527 94.8494 40.6581C94.8037 40.7362 94.7809 40.7753 94.7809 40.7753C94.6395 41.077 94.5437 41.3006 94.4937 41.4461L94.2831 42.0307L94.2014 42.3498C94.1861 42.3759 94.184 42.4095 94.1948 42.4508C94.2002 42.4714 94.1953 42.4948 94.1801 42.5208L94.211 42.5127C94.2306 42.4193 94.2557 42.3466 94.2861 42.2945L94.3465 42.1464C94.3671 42.1409 94.3802 42.1486 94.3856 42.1692C94.4431 42.2203 94.436 42.2773 94.3643 42.3402C94.3436 42.3456 94.336 42.3586 94.3414 42.3793L94.3495 42.4102L94.4114 42.394L94.5322 42.0976C94.6432 41.848 94.7161 41.6635 94.7509 41.544L94.8047 41.4969L94.8209 41.5588L94.6839 41.7932C94.6535 41.8453 94.641 41.8816 94.6464 41.9023L94.6626 41.9642L94.7164 41.917C94.7056 41.8757 94.7105 41.8524 94.7311 41.847C94.767 41.8155 94.7952 41.7971 94.8159 41.7917C94.7962 41.885 94.7891 41.942 94.7946 41.9627L94.5693 42.6172L94.5855 42.6792ZM97.42 38.0981L97.4966 38.0119L97.7331 37.6521C97.6505 37.6738 97.5995 37.7313 97.5798 37.8246L97.3809 38.0753C97.3809 38.0753 97.3836 38.0856 97.389 38.1062C97.389 38.1062 97.3787 38.109 97.3581 38.1144L97.42 38.0981ZM97.012 37.0472C97.0066 37.0266 96.9936 37.019 96.973 37.0244L96.9192 37.0716L96.9664 37.1254L97.012 37.0472ZM103.952 41.1818C103.931 41.1872 103.89 41.198 103.828 41.2143C103.787 41.2251 103.753 41.2229 103.727 41.2077C103.66 41.2033 103.588 41.2222 103.511 41.2645C103.428 41.2861 103.366 41.3024 103.325 41.3132L102.993 41.4335L102.984 41.4025L103.385 41.165C103.581 41.0696 103.71 41.0138 103.771 40.9976L104.058 40.9555L104.925 40.7281L105.172 40.6632L105.296 40.6307L105.327 40.6226C105.327 40.6226 105.33 40.6329 105.335 40.6536C105.335 40.6536 105.325 40.6563 105.304 40.6617L104.995 40.7429L104.57 40.8875C104.534 40.9189 104.475 40.9455 104.392 40.9671L104.161 41.094C104.104 41.1309 104.035 41.1601 103.952 41.1818ZM97.1653 36.8747L97.3023 36.6403L97.2942 36.6093C97.1768 36.7504 97.1105 36.834 97.0952 36.86L97.1034 36.891L97.1653 36.8747ZM97.8168 36.8362L97.7777 36.8133L97.7158 36.8296L97.7092 36.9305L97.8168 36.8362ZM98.2694 37.0483L98.3379 36.9311L98.3298 36.9001L98.2989 36.9082L98.2222 36.9945L98.2075 37.0645L98.2694 37.0483ZM102.777 39.6042C102.844 39.5206 102.98 39.4518 103.186 39.3977C103.186 39.3977 103.212 39.4129 103.265 39.4433L103.211 39.4905C103.164 39.4807 103.099 39.4866 103.017 39.5083C102.914 39.5353 102.834 39.5673 102.777 39.6042ZM98.513 35.9588L98.5049 35.9279C98.4744 35.98 98.4233 36.0375 98.3516 36.1004L98.3598 36.1314L98.513 35.9588ZM103.326 40.0558C103.326 40.0558 103.316 40.0585 103.295 40.0639C103.29 40.0433 103.297 40.0303 103.318 40.0248C103.333 39.9988 103.312 39.9602 103.254 39.9092L103.479 39.8833L103.425 39.9305C103.477 39.9609 103.504 39.9761 103.504 39.9761L103.974 39.7534L103.851 39.7859L103.842 39.7549C104.049 39.7008 104.211 39.6472 104.33 39.594L104.422 39.5697C104.468 39.4915 104.538 39.4623 104.631 39.4819L104.941 39.4007C105.023 39.3791 105.043 39.3297 105.001 39.2526L105.032 39.2444L105.125 39.2201C105.196 39.1572 105.243 39.123 105.263 39.1176L105.348 39.0623L105.604 39.0283C105.609 39.0489 105.602 39.0619 105.581 39.0673L105.713 39.0658L105.752 39.0887C105.731 39.0941 105.724 39.1071 105.729 39.1277C105.693 39.1592 105.634 39.1857 105.551 39.2074C105.536 39.2334 105.508 39.2519 105.467 39.2627C105.436 39.3148 105.405 39.3229 105.374 39.2871L105.266 39.3814C105.23 39.4129 105.182 39.4367 105.12 39.453C105.078 39.4638 105.04 39.485 105.004 39.5164L104.965 39.4936C104.995 39.4415 104.969 39.4263 104.887 39.4479L104.284 39.6722C104.264 39.7656 104.213 39.8231 104.131 39.8447C104.043 39.8457 103.988 39.8489 103.968 39.8544C103.849 39.9075 103.677 39.9638 103.45 40.0233C103.45 40.0233 103.432 40.0391 103.396 40.0705C103.375 40.0759 103.352 40.071 103.326 40.0558ZM104.243 39.5174C104.293 39.372 104.437 39.2901 104.675 39.2718L104.683 39.3028L104.243 39.5174ZM99.1158 35.7345L99.2381 35.5701C99.2327 35.5495 99.2197 35.5419 99.199 35.5473L99.0767 35.7117L99.0849 35.7427L99.1158 35.7345ZM101.075 33.9966C101.136 33.8924 101.184 33.8246 101.22 33.7931L101.106 33.9885L101.075 33.9966ZM100.133 33.0528C100.127 33.0322 100.114 33.0246 100.094 33.03L99.9257 33.2725L100.133 33.0528ZM101.65 33.4156C101.66 33.3689 101.701 33.3141 101.773 33.2512C101.778 33.2719 101.763 33.2979 101.727 33.3294C101.691 33.3608 101.679 33.3972 101.689 33.4385L101.65 33.4156ZM101.008 32.8564C101.068 32.7522 101.099 32.7002 101.099 32.7002C101.119 32.6947 101.13 32.692 101.13 32.692C101.124 32.6714 101.122 32.6611 101.122 32.6611L101.083 32.6382C101.052 32.6903 101.037 32.7164 101.037 32.7164L100.952 32.7717C100.958 32.7923 100.95 32.8054 100.929 32.8108C100.924 32.7901 100.921 32.7798 100.921 32.7798C100.916 32.7592 100.923 32.7462 100.944 32.7407C101.005 32.6366 101.066 32.5763 101.128 32.5601C101.154 32.5753 101.167 32.5829 101.167 32.5829C101.183 32.5569 101.177 32.5363 101.151 32.521C101.125 32.5058 101.12 32.4852 101.135 32.4591C101.15 32.4331 101.155 32.4097 101.15 32.3891L101.181 32.381L101.22 32.4038C101.189 32.4559 101.195 32.4765 101.236 32.4657L101.244 32.4967C101.265 32.4913 101.275 32.4886 101.275 32.4886C101.27 32.4679 101.267 32.4576 101.267 32.4576C101.312 32.3795 101.338 32.3507 101.343 32.3713C101.39 32.3812 101.411 32.3757 101.405 32.3551C101.415 32.3084 101.417 32.2748 101.412 32.2541L101.396 32.1922C101.354 32.203 101.326 32.2215 101.311 32.2475L101.296 32.3176L101.242 32.3647L101.226 32.3028L101.187 32.28C101.172 32.3061 101.146 32.3348 101.111 32.3663C101.075 32.3977 101.052 32.4368 101.042 32.4835L100.957 32.5388C100.926 32.5029 100.895 32.5111 100.864 32.5631C100.844 32.5686 100.811 32.6103 100.765 32.6885L100.796 32.6804L100.873 32.5941L100.934 32.5779L100.943 32.6088C100.943 32.6088 100.912 32.6609 100.851 32.7651C100.857 32.7857 100.849 32.7988 100.828 32.8042C100.823 32.7835 100.82 32.7732 100.82 32.7732C100.759 32.8774 100.742 32.9371 100.768 32.9523L100.799 32.9442L100.876 32.858C100.886 32.8992 100.905 32.9275 100.931 32.9427L101.008 32.8564ZM100.457 32.2729C100.478 32.2675 100.486 32.2545 100.48 32.2338L100.58 32.1085L100.679 31.9832L100.663 31.9213L100.632 31.9294L100.58 32.1085C100.533 32.0987 100.505 32.1171 100.495 32.1638C100.48 32.1898 100.465 32.2159 100.449 32.2419L100.457 32.2729ZM102.127 32.3313L102.096 32.3394C102.035 32.4436 101.987 32.5114 101.951 32.5429C101.956 32.5635 101.959 32.5738 101.959 32.5738C101.98 32.5684 101.99 32.5657 101.99 32.5657L102.127 32.3313ZM101.503 32.0978L101.657 31.9253L101.609 31.8715C101.579 31.9236 101.528 31.9811 101.456 32.0441C101.441 32.0701 101.439 32.1038 101.449 32.145L101.503 32.0978ZM100.956 31.7782C100.971 31.7521 100.982 31.7494 100.987 31.77C101.008 31.7646 101.015 31.7516 101.01 31.731C101.076 31.6474 101.13 31.5562 101.17 31.4575C101.129 31.4683 101.078 31.5258 101.017 31.63C101.017 31.63 101.001 31.656 100.971 31.7081L100.956 31.7782ZM102.676 31.5255L102.668 31.4945L102.241 32.1359C102.262 32.1305 102.275 32.1381 102.28 32.1587L102.676 31.5255ZM101.88 31.1388L101.872 31.1079L101.681 31.3895L101.689 31.4204L101.88 31.1388ZM101.216 31.3793C101.369 31.2068 101.453 31.1075 101.468 31.0815L101.591 30.9171C101.723 30.7499 101.789 30.6224 101.788 30.5345L101.666 30.6989L101.452 31.0196L101.176 31.3565L101.185 31.3874L101.216 31.3793ZM101.623 31.0409L101.576 30.9871L101.561 31.0571L101.6 31.0799L101.623 31.0409ZM101.978 31.5102C102.008 31.4581 102.023 31.4321 102.023 31.4321C102.084 31.3279 102.12 31.2525 102.129 31.2058L102.191 31.1896C102.289 31.1419 102.317 31.0794 102.275 31.0023C102.254 31.0077 102.249 31.0311 102.26 31.0723C102.265 31.093 102.242 31.0881 102.19 31.0576L101.931 31.4565L101.978 31.5102ZM101.995 30.3147L101.964 30.3229L101.834 30.4563C101.839 30.477 101.831 30.49 101.811 30.4954C101.852 30.4846 101.873 30.4792 101.873 30.4792L101.995 30.3147ZM102.048 30.8963L102.102 30.8491L102.438 30.364C102.438 30.364 102.468 30.3119 102.529 30.2077L102.498 30.2158C102.483 30.2419 102.465 30.2576 102.445 30.263C102.424 30.2684 102.409 30.2945 102.399 30.3411C102.368 30.3932 102.34 30.4117 102.314 30.3964C102.294 30.4019 102.286 30.4149 102.291 30.4355L102.009 30.8734L101.986 30.9125L102.048 30.8963ZM102.565 30.5954L102.557 30.5644L102.526 30.5725C102.526 30.5725 102.495 30.6246 102.434 30.7288C102.44 30.7494 102.443 30.7598 102.443 30.7598C102.463 30.7544 102.473 30.7516 102.473 30.7516L102.565 30.5954ZM101.977 30.1209L101.938 30.0981L101.87 30.2153C101.875 30.2359 101.878 30.2462 101.878 30.2462C101.898 30.2408 101.909 30.2381 101.909 30.2381L101.977 30.1209ZM102.018 30.2757C102.048 30.2236 102.063 30.1975 102.063 30.1975L102.055 30.1666L101.979 30.2528L102.018 30.2757ZM102.371 29.9844C102.366 29.9638 102.353 29.9562 102.332 29.9616L102.279 30.0088L102.326 30.0626L102.371 29.9844ZM102.629 30.0824C102.623 30.0617 102.61 30.0541 102.59 30.0595C102.569 30.0649 102.543 30.0937 102.513 30.1458C102.513 30.1458 102.516 30.1561 102.521 30.1767C102.521 30.1767 102.531 30.174 102.552 30.1686L102.629 30.0824ZM102.616 30.2843C102.636 30.2789 102.644 30.2659 102.638 30.2452C102.699 30.141 102.73 30.0889 102.73 30.0889L102.883 29.9164C102.913 29.8643 102.929 29.8383 102.929 29.8383C102.887 29.8491 102.859 29.8675 102.844 29.8936C102.844 29.8936 102.829 29.9196 102.798 29.9717C102.778 29.9771 102.76 29.9929 102.744 30.0189C102.729 30.045 102.724 30.0683 102.73 30.0889C102.709 30.0944 102.684 30.1231 102.653 30.1752C102.617 30.2067 102.602 30.2327 102.607 30.2534L102.616 30.2843ZM102.461 29.6962L102.53 29.579L102.575 29.5008L102.545 29.509L102.422 29.6734L102.438 29.7353L102.461 29.6962ZM102.705 29.9961L102.996 29.5891L102.979 29.5272C102.985 29.5479 102.977 29.5609 102.957 29.5663C102.941 29.5923 102.916 29.6211 102.88 29.6526C102.844 29.684 102.814 29.7361 102.789 29.8088C102.773 29.8349 102.738 29.8664 102.681 29.9032C102.645 29.9347 102.635 29.9814 102.652 30.0433L102.705 29.9961ZM103.002 29.4882C103.136 29.409 103.199 29.3151 103.193 29.2065L103.002 29.4882ZM103.446 28.28L103.406 28.1252L103.412 28.0242L103.381 28.0324C103.377 28.0997 103.388 28.1849 103.415 28.2881L103.423 28.3191L103.446 28.28ZM103.753 27.3062L103.807 27.259L103.955 27.3194C103.935 27.3248 103.917 27.3406 103.901 27.3666C103.901 27.3666 103.891 27.3693 103.87 27.3747L103.753 27.3062ZM105.099 45.9756C105.037 45.9918 104.996 45.9586 104.974 45.8761C104.969 45.8555 104.966 45.8452 104.966 45.8452C104.945 45.8506 104.935 45.8533 104.935 45.8533C104.877 45.8022 104.864 45.7506 104.894 45.6985L104.878 45.6366L104.846 45.5128L104.837 45.4818L104.784 45.529L104.769 45.599C104.739 45.6511 104.708 45.6593 104.676 45.6234C104.665 45.5821 104.629 45.5696 104.567 45.5859C104.552 45.6119 104.539 45.6043 104.528 45.563C104.517 45.5217 104.48 45.4653 104.417 45.3935L104.409 45.3626C104.306 45.3896 104.275 45.3538 104.315 45.255L104.344 45.115L104.352 45.1459L104.4 45.1997L104.445 45.1216L104.375 45.1068L104.344 45.115L104.503 44.7095C104.503 44.7095 104.513 44.7068 104.534 44.7014C104.534 44.7014 104.531 44.6911 104.525 44.6705L104.494 44.6786C104.474 44.684 104.464 44.6867 104.464 44.6867C104.469 44.7073 104.472 44.7176 104.472 44.7176C104.42 44.6872 104.386 44.685 104.371 44.7111L104.234 44.9455L104.18 44.9927L104.188 45.0236C104.193 45.0443 104.175 45.06 104.134 45.0708C104.093 45.0816 104.067 45.0664 104.056 45.0251C104.019 44.9687 104.031 44.8883 104.092 44.7841C104.142 44.6387 104.167 44.522 104.166 44.434C104.186 44.4286 104.194 44.4156 104.189 44.3949C104.168 44.4003 104.158 44.403 104.158 44.403L104.127 44.4112C104.096 44.4633 104.045 44.5208 103.973 44.5837C103.979 44.6043 103.981 44.6146 103.981 44.6146C103.961 44.6201 103.951 44.6228 103.951 44.6228L103.934 44.5609L104.003 44.4436L103.995 44.4127L103.933 44.4289C103.944 44.4702 103.923 44.4756 103.871 44.4452C103.83 44.456 103.801 44.4744 103.786 44.5005C103.756 44.5526 103.74 44.5786 103.74 44.5786L103.724 44.5167L103.716 44.4858L103.7 44.4238C103.678 44.3413 103.705 44.2349 103.782 44.1047C103.816 43.9853 103.895 43.8214 104.016 43.613L104.245 43.2223L104.496 42.7925C104.491 42.7718 104.498 42.7588 104.519 42.7534C104.636 42.6123 104.842 42.2607 105.135 41.6985L105.308 41.223C105.339 41.1709 105.382 41.0825 105.437 40.9576C105.487 40.8122 105.556 40.695 105.643 40.606L105.956 40.16L106.147 39.8783C106.239 39.81 106.342 39.7829 106.456 39.7972C106.585 39.7853 106.733 39.8017 106.899 39.8464C106.94 39.8356 107 39.853 107.078 39.8986C107.151 39.9237 107.249 39.92 107.373 39.8875C107.518 39.8496 107.624 39.8768 107.692 39.9692L107.7 40.0001C107.706 40.0208 107.711 40.0414 107.717 40.062C107.737 40.0566 107.755 40.0409 107.77 40.0148C107.791 40.0094 107.804 40.017 107.81 40.0377C107.806 40.193 107.849 40.3141 107.938 40.401C108.001 40.4727 108.038 40.5292 108.049 40.5705C108.065 40.6324 108.06 40.6997 108.035 40.7724C108.031 40.8398 108.031 40.8837 108.037 40.9044L108.014 40.9434C108.03 41.0053 108.026 41.0727 108.001 41.1454C107.97 41.1975 107.948 41.2366 107.932 41.2626L107.842 41.5508L107.782 41.699L107.5 42.1369L107.234 42.6367L106.847 43.4329L106.611 43.7926L106.337 44.2615C106.215 44.4699 106.111 44.6185 106.024 44.7075L105.955 44.8247L105.849 45.051L105.65 45.3017L105.246 45.904C105.231 45.9301 105.21 45.9355 105.184 45.9203C105.143 45.9311 105.115 45.9495 105.099 45.9756ZM104.109 44.2173L104.078 44.2254L104.009 44.3427C104.009 44.3427 104.02 44.34 104.04 44.3345C104.04 44.3345 104.043 44.3449 104.048 44.3655L104.109 44.2173ZM104.579 44.6233L104.702 44.4589L104.693 44.4279L104.662 44.436C104.662 44.436 104.632 44.4881 104.571 44.5923C104.55 44.5977 104.54 44.6004 104.54 44.6004C104.546 44.6211 104.548 44.6314 104.548 44.6314L104.579 44.6233ZM104.163 44.1701L104.093 44.1554L104.039 44.2026C104.039 44.2026 104.049 44.1999 104.07 44.1945C104.075 44.2151 104.075 44.2151 104.07 44.1945L104.163 44.1701ZM104.234 44.3168L104.334 44.1914C104.328 44.1708 104.336 44.1578 104.356 44.1524L104.326 44.1605C104.284 44.1713 104.256 44.1898 104.241 44.2158C104.226 44.2419 104.21 44.2679 104.195 44.2939L104.203 44.3249L104.234 44.3168ZM104.269 43.9438C104.269 43.9438 104.266 43.9335 104.261 43.9129C104.261 43.9129 104.271 43.9102 104.292 43.9048L104.23 43.921L104.199 43.9291L104.168 43.9372L104.184 43.9991C104.189 44.0198 104.202 44.0274 104.223 44.022L104.269 43.9438ZM104.433 44.0661C104.422 44.0248 104.437 43.9988 104.479 43.988L104.533 43.9408L104.624 43.7845L104.692 43.6673L104.63 43.6835C104.559 43.7464 104.518 43.8012 104.508 43.8479C104.493 43.874 104.478 43.9 104.463 43.9261C104.432 43.9782 104.409 44.0172 104.394 44.0433C104.373 44.0487 104.363 44.0514 104.363 44.0514C104.368 44.072 104.371 44.0824 104.371 44.0824L104.41 44.1052L104.433 44.0661ZM104.398 43.6784L104.367 43.6866L104.313 43.7338L104.36 43.7875L104.398 43.6784ZM104.497 43.5531C104.497 43.5531 104.494 43.5428 104.489 43.5222C104.489 43.5222 104.479 43.5249 104.458 43.5303C104.52 43.514 104.558 43.4929 104.574 43.4668C104.574 43.4668 104.604 43.4148 104.665 43.3106L104.688 43.2715C104.682 43.2509 104.669 43.2432 104.649 43.2487C104.649 43.2487 104.651 43.259 104.657 43.2796C104.657 43.2796 104.647 43.2823 104.626 43.2877L104.557 43.4049L104.458 43.5303C104.437 43.5357 104.43 43.5487 104.435 43.5693C104.414 43.5748 104.404 43.5775 104.404 43.5775C104.41 43.5981 104.412 43.6084 104.412 43.6084C104.418 43.6291 104.431 43.6367 104.451 43.6313L104.497 43.5531ZM104.532 44.5695L104.601 44.4523C104.708 44.3579 104.8 44.2456 104.876 44.1153L104.907 44.1072L104.915 44.1382L104.847 44.2554L104.747 44.3807L104.824 44.2945C104.824 44.2945 104.821 44.2841 104.816 44.2635C104.816 44.2635 104.826 44.2608 104.847 44.2554C105.097 43.9472 105.204 43.8089 105.168 43.8403L105.16 43.8094L105.129 43.8175C105.118 43.7762 105.13 43.7398 105.166 43.7084C105.182 43.6823 105.199 43.6666 105.22 43.6612C105.266 43.583 105.314 43.5152 105.365 43.4577C105.396 43.4056 105.426 43.3535 105.457 43.3014C105.472 43.2754 105.487 43.2493 105.502 43.2233C105.517 43.1972 105.52 43.1636 105.509 43.1223L105.571 43.1061L105.677 42.8798L105.646 42.8879L105.509 43.1223L105.065 43.7018C104.883 44.0144 104.73 44.2309 104.607 44.3513L104.493 44.5466L104.501 44.5776L104.532 44.5695ZM104.742 43.2243L104.947 42.8727L104.939 42.8417L104.885 42.8889L104.748 43.1233L104.717 43.1314L104.694 43.1705L104.711 43.2324L104.742 43.2243ZM104.95 43.1365C105.011 43.0323 105.041 42.9802 105.041 42.9802L105.064 42.9412L105.033 42.9493L104.919 43.1446L104.95 43.1365ZM105.402 42.588L105.394 42.557C105.394 42.557 105.363 42.6091 105.302 42.7133L105.402 42.588ZM105.198 42.4429C105.229 42.3908 105.265 42.3593 105.306 42.3485L105.267 42.3256L105.236 42.3338L105.182 42.381L105.159 42.42L105.198 42.4429ZM106.002 41.4711L105.971 41.4793L105.94 41.4874L105.88 41.6356C105.885 41.6562 105.898 41.6638 105.919 41.6584L106.002 41.4711ZM20.3007 93.3518C20.2388 93.3681 20.1741 93.374 20.1068 93.3696C20.0601 93.3598 20.0058 93.363 19.9439 93.3792C19.8973 93.3694 19.8457 93.3829 19.7892 93.4198C19.7273 93.4361 19.6523 93.4447 19.5644 93.4457L19.1605 93.4193L19.0986 93.4355C19.0563 93.3584 18.9885 93.31 18.8951 93.2904C18.8017 93.2708 18.729 93.2458 18.6769 93.2153C18.5835 93.1957 18.5005 93.1734 18.4278 93.1483C18.3702 93.0973 18.3078 93.0695 18.2405 93.0651C18.2091 93.0293 18.1673 92.9961 18.1152 92.9657C18.0631 92.9352 18.0083 92.8945 17.9508 92.8434L18.0208 92.8581L17.4951 92.3674C17.3432 92.2088 17.1871 91.9079 17.0268 91.4647L16.8542 91.3115C16.8282 91.2962 16.8125 91.2783 16.807 91.2577C16.8169 91.211 16.8191 91.1773 16.8136 91.1567C16.6858 90.8374 16.6083 90.6261 16.5812 90.5229C16.5109 90.2547 16.4644 90.0353 16.4417 89.8648C16.5371 90.0603 16.5983 90.2097 16.6254 90.3128L16.6563 90.3047C16.6185 90.1603 16.5464 89.9697 16.4402 89.7329L16.4092 89.741C16.4201 89.7822 16.4179 89.8159 16.4026 89.842C16.3343 89.7496 16.2704 89.5899 16.2108 89.3629C16.1459 89.1153 16.1048 88.9166 16.0875 88.7667C16.0757 88.6375 16.0461 88.3144 15.9987 87.7975C16.0031 87.7302 15.9994 87.6319 15.9876 87.5027C15.9909 87.3474 15.9818 87.2285 15.9602 87.146C15.9439 87.0841 15.9174 87.0249 15.8805 86.9684C15.8589 86.8859 15.8475 86.8006 15.8465 86.7127C15.8611 86.1795 15.9103 85.7365 15.9942 85.3837C16.0486 85.1709 16.0689 84.912 16.0551 84.6068C16.0747 84.5135 16.0943 84.4201 16.1139 84.3267C16.1488 84.2073 16.1809 84.0776 16.2103 83.9375C16.23 83.8442 16.2366 83.7432 16.2301 83.6346C16.2389 83.5 16.2607 83.373 16.2956 83.2535C16.324 83.0255 16.3507 82.8752 16.3758 82.8024C16.3856 82.7558 16.3797 82.6911 16.358 82.6086L16.3499 82.5776L16.5442 81.9312L16.7873 81.4704C16.8874 81.1795 16.95 80.9977 16.975 80.925C17.0457 80.7741 17.1295 80.6308 17.2262 80.4952C17.3436 80.3541 17.4376 80.2081 17.5084 80.0573L17.8899 79.494C18.0269 79.2596 18.1623 79.1028 18.2959 79.0236C18.7262 78.6461 19.0543 78.3836 19.2803 78.2361L19.4564 78.0245C19.5433 77.9356 19.6796 77.8667 19.8654 77.818L20.5072 77.6166C20.6311 77.5841 20.7126 77.4745 20.7518 77.2878L20.7879 77.0467L20.8107 77.0077L20.8416 76.9995C20.9035 76.9833 20.9633 77.0007 21.0208 77.0518C21.0935 77.0768 21.1483 77.1176 21.1852 77.1741L21.3186 77.3045C21.3609 77.3816 21.4211 77.443 21.4993 77.4887C21.5774 77.5344 21.6425 77.5724 21.6946 77.6029C21.7153 77.5975 21.7283 77.6051 21.7337 77.6257C21.7032 77.6778 21.7195 77.7397 21.7824 77.8114C21.7932 77.8527 21.8301 77.9092 21.893 77.9809L21.9159 77.9418C21.9257 77.8952 21.917 77.8202 21.89 77.717L21.9438 77.6699L22.4877 77.7257C22.5757 77.7247 22.6479 77.7057 22.7044 77.6688C22.7196 77.6428 22.7479 77.6244 22.7891 77.6135C22.851 77.5973 22.895 77.5968 22.9211 77.612C22.9678 77.6218 23.0144 77.6316 23.0611 77.6414L23.1002 77.6643C23.224 77.6318 23.2424 77.66 23.1555 77.749L23.5122 77.7216C23.699 77.7609 23.8314 77.8033 23.9095 77.849C24.0658 77.9403 24.1597 78.0039 24.1912 78.0398C24.228 78.0963 24.2855 78.1474 24.3637 78.193C24.4418 78.2387 24.5069 78.2767 24.559 78.3072L24.5915 78.431C24.7163 78.4865 24.8124 78.5164 24.8797 78.5208C24.947 78.5252 25.0035 78.4883 25.0492 78.4102C25.0763 78.5134 25.1158 78.5802 25.1679 78.6106C25.2407 78.6357 25.2901 78.6558 25.3161 78.671C25.4095 78.6906 25.4643 78.7314 25.4805 78.7933C25.4913 78.8346 25.4995 78.8655 25.5049 78.8862L25.5602 78.9709C25.775 79.2013 25.923 79.4712 26.0042 79.7808L26.2056 80.4227C26.2922 80.7528 26.3548 81.2437 26.3934 81.8952L26.4106 82.7177C26.4038 83.0283 26.4091 83.2585 26.4263 83.4083L26.4537 83.7651L26.439 83.8351L26.4065 83.7113L26.3396 83.9604C26.3254 84.0744 26.3013 84.2351 26.2675 84.4425C26.2489 84.6238 26.2075 84.8442 26.1432 85.1037C25.9483 85.7061 25.8183 86.0931 25.753 86.2646C25.6887 86.5241 25.606 86.7553 25.5048 86.9583L25.5292 87.0512C25.5705 87.0403 25.5884 87.0246 25.583 87.004C25.6036 86.9985 25.6498 86.9644 25.7215 86.9015C25.6921 87.0415 25.6388 87.1327 25.5617 87.175C25.3509 87.2964 25.2264 87.4945 25.1882 87.7692C25.2 87.8984 25.1581 88.0748 25.0624 88.2984C24.5752 89.1319 24.3317 89.5487 24.3317 89.5487C24.3317 89.5487 24.1338 89.8873 23.738 90.5646C23.7227 90.5906 23.7205 90.6243 23.7314 90.6655C23.7368 90.6862 23.7319 90.7095 23.7167 90.7356L23.6644 90.9147L23.5989 91.2958C23.5282 91.4466 23.4278 91.484 23.2975 91.4079L23.1494 91.3475L23.0956 91.3947C22.8987 91.8213 22.7801 92.084 22.7399 92.1827L22.6957 92.3928L22.6176 92.3471C22.6176 92.3471 22.6023 92.3732 22.5719 92.4253L22.5115 92.5734L22.3796 92.575C22.3383 92.5858 22.2796 92.6563 22.2035 92.7866C22.2089 92.8072 22.191 92.8229 22.1497 92.8338C22.1291 92.8392 22.1188 92.8419 22.1188 92.8419C22.0613 92.7908 22.0043 92.7837 21.9478 92.8206C21.8913 92.8574 21.8424 92.8813 21.8011 92.8921C21.6469 92.9767 21.4921 93.0173 21.3368 93.0139C21.3162 93.0193 21.2646 93.0328 21.1821 93.0545C21.1202 93.0707 21.074 93.1049 21.0435 93.157C21.0077 93.1884 20.9485 93.215 20.8659 93.2366L20.3007 93.3518ZM17.1298 90.9745C17.1244 90.9539 17.0902 90.9077 17.0273 90.836L16.9963 90.8441C17.0745 90.8898 17.1189 90.9333 17.1298 90.9745ZM19.1113 91.8443C19.1265 91.8182 19.1368 91.8155 19.1422 91.8361C19.1628 91.8307 19.1835 91.8253 19.2041 91.8199L19.5822 91.6215C19.5301 91.5911 19.4937 91.5785 19.4731 91.584C19.4318 91.5948 19.3699 91.611 19.2873 91.6327C19.1994 91.6337 19.1272 91.6526 19.0707 91.6895C19.0348 91.721 18.9653 91.7502 18.8621 91.7773C18.7742 91.7783 18.7019 91.7972 18.6454 91.8341C18.6042 91.8449 18.5499 91.8482 18.4826 91.8438C18.4359 91.8339 18.4103 91.8627 18.4059 91.93L18.375 91.9381C18.287 91.9391 18.1497 91.92 17.963 91.8808L17.6747 91.791C17.7377 91.8627 17.8158 91.9084 17.9092 91.928C17.9146 91.9486 17.933 91.9769 17.9645 92.0127C17.9905 92.0279 18.0188 92.0095 18.0492 91.9574C18.0807 91.9933 18.117 92.0058 18.1583 91.995C18.2202 91.9787 18.2539 91.9809 18.2593 92.0016C18.2853 92.0168 18.319 92.019 18.3603 92.0082L18.6779 91.9579L18.5998 91.9123L18.9337 91.9239L19.1113 91.8443ZM19.2772 92.0985C19.2251 92.068 19.1784 92.0582 19.1371 92.0691L19.1453 92.1L19.2772 92.0985ZM17.8138 91.0598L17.6347 91.0075C17.6922 91.0586 17.7339 91.0917 17.76 91.107L17.8219 91.0907L17.8138 91.0598ZM17.4733 91.1491L17.4571 91.0872C17.4777 91.0818 17.4907 91.0894 17.4961 91.11C17.5168 91.1046 17.5401 91.1095 17.5662 91.1247C17.5239 91.0476 17.4506 90.9786 17.3464 90.9177C17.2629 90.8514 17.2233 90.7846 17.2277 90.7173L17.1414 90.6406C17.136 90.62 17.123 90.6124 17.1024 90.6178C17.0861 90.5559 17.065 90.5173 17.0389 90.5021L17.179 90.5315C17.09 90.4446 17.0455 90.4011 17.0455 90.4011C16.9772 90.3088 16.9062 90.2061 16.8324 90.0931L16.8015 90.1012C16.7754 90.086 16.7597 90.0681 16.7543 90.0475C16.7435 90.0062 16.725 89.9779 16.699 89.9627L16.7233 90.0556L16.7314 90.0865L16.8015 90.1012C16.7862 90.1273 16.7867 90.1713 16.803 90.2332C16.8192 90.2951 16.8696 90.4032 16.9542 90.5574C16.9813 90.6606 17.0078 90.7198 17.0339 90.735C17.1391 90.8839 17.2752 91.0246 17.4423 91.1572L17.4733 91.1491ZM18.8753 91.5753C18.9785 91.5483 19.0637 91.5369 19.131 91.5413L19.1229 91.5104L18.5399 91.4317L18.9387 91.691L18.8753 91.5753ZM18.2989 91.3957L18.3689 91.4104C18.5242 91.4138 18.6094 91.4025 18.6246 91.3764C18.6811 91.3395 18.7327 91.326 18.7794 91.3358C18.8467 91.3402 18.8983 91.3267 18.9342 91.2952C18.97 91.2638 19.0292 91.2372 19.1118 91.2156C19.1943 91.1939 19.2535 91.1674 19.2894 91.1359L19.3594 91.1506L19.4979 91.0481L19.6055 90.9537L19.5974 90.9228C19.618 90.9174 19.6436 90.8886 19.674 90.8365L18.1817 91.3272L18.1345 91.2734C18.1399 91.294 18.1426 91.3044 18.1426 91.3044L17.4195 91.1963C17.4195 91.1963 17.5107 91.2496 17.693 91.3561C17.7451 91.3866 17.7945 91.4067 17.8412 91.4165C17.9085 91.4209 17.9655 91.428 18.0122 91.4378L17.8965 91.5012L18.0056 91.5388L18.1294 91.5063L18.3623 91.5114L18.2989 91.3957ZM19.2762 91.3379C19.3229 91.3477 19.3435 91.3423 19.3381 91.3216C19.3273 91.2803 19.3191 91.2494 19.3137 91.2288L19.1442 91.3394L19.2762 91.3379ZM19.1011 92.3101C19.163 92.2938 19.2483 92.2825 19.3569 92.2761C19.4807 92.2436 19.5708 92.2089 19.6273 92.1721C20.3117 91.8382 20.8012 91.4341 21.0958 90.9598L21.1252 90.8198L21.0486 90.906L21.0177 90.9142C20.9666 90.9717 20.9155 91.0292 20.8644 91.0867C20.834 91.1388 20.8035 91.1909 20.7731 91.243C20.6949 91.1973 20.6797 91.2234 20.7274 91.3211C20.7068 91.3265 20.6861 91.3319 20.6655 91.3374C20.6395 91.3221 20.6188 91.3275 20.6036 91.3536L20.2646 91.5748L20.2499 91.6449C20.188 91.6611 20.1391 91.6849 20.1033 91.7164C20.062 91.7272 20.0055 91.7641 19.9338 91.827L19.6877 92.0239C19.6106 92.0662 19.541 92.0954 19.4791 92.1117C19.4325 92.1019 19.3885 92.1024 19.3472 92.1132L19.3163 92.1213C19.2544 92.1376 19.2158 92.1587 19.2006 92.1847L19.1387 92.201L19.0849 92.2482L19.0296 92.1634C19.0089 92.1688 18.9834 92.1976 18.9529 92.2497C18.9377 92.2757 18.9041 92.2735 18.852 92.2431C18.8466 92.2225 18.8362 92.2252 18.821 92.2512C18.8318 92.2925 18.8476 92.3104 18.8682 92.305C18.9616 92.3246 19.0392 92.3263 19.1011 92.3101ZM20.3007 91.3338L20.2925 91.3028C20.2361 91.3397 20.1796 91.3766 20.1231 91.4135C20.0872 91.4449 20.0514 91.4764 20.0155 91.5078L20.0236 91.5388L20.3007 91.3338ZM19.4147 91.2354C19.6102 91.14 19.7699 91.076 19.8937 91.0435C19.7591 91.0348 19.6608 91.0385 19.5989 91.0547L19.5679 91.0628C19.569 91.1508 19.5125 91.1877 19.3985 91.1734L19.3447 91.2206L19.4147 91.2354ZM19.985 90.8873C20.0057 90.8819 20.0057 90.8819 19.985 90.8873C19.9796 90.8666 19.9769 90.8563 19.9769 90.8563C19.9357 90.8671 19.9074 90.8856 19.8922 90.9116L19.8384 90.9588C19.8797 90.948 19.9003 90.9426 19.9003 90.9426L19.985 90.8873ZM19.7506 90.7503C19.9766 90.6028 20.2362 90.4575 20.5295 90.3144L20.5214 90.2834L19.7344 90.6884L19.7506 90.7503ZM20.5488 90.6401L20.5097 90.6173C20.4891 90.6227 20.4636 90.6515 20.4331 90.7036L20.4641 90.6955L20.5488 90.6401ZM21.3175 90.6701C21.2915 90.6549 21.2785 90.6473 21.2785 90.6473C21.2937 90.6212 21.2883 90.6006 21.2622 90.5854L21.1922 90.5706C21.1313 90.6748 21.1009 90.7269 21.1009 90.7269L21.2556 90.6863L21.3175 90.6701ZM22.8236 91.3668L22.7926 91.3749C22.772 91.3803 22.7465 91.4091 22.716 91.4612C22.7366 91.4558 22.7497 91.4634 22.7551 91.484L22.8236 91.3668ZM20.6061 90.2281C20.6268 90.2227 20.673 90.1885 20.7447 90.1256L20.7365 90.0947L20.6061 90.2281ZM21.3323 90.6001C21.3269 90.5794 21.3394 90.5431 21.3698 90.491L21.2998 90.4763L21.2851 90.5463L21.3323 90.6001ZM20.5036 90.0896C20.5243 90.0842 20.5705 90.05 20.6422 89.9871L20.6031 89.9643L20.5036 90.0896ZM23.434 91.8022C23.4645 91.7501 23.49 91.7213 23.5106 91.7159C23.5106 91.7159 23.5367 91.7311 23.5888 91.7616L23.434 91.8022ZM21.3845 90.4209C21.416 90.4568 21.4393 90.4617 21.4546 90.4357C21.4904 90.4042 21.5187 90.3858 21.5393 90.3804L21.4302 90.3428L21.3373 90.3672L21.3845 90.4209ZM20.9045 89.8521C20.9762 89.7892 21.0914 89.6818 21.2501 89.5299L21.2419 89.499L20.8736 89.8602L20.9045 89.8521ZM21.5302 89.5888C21.5095 89.5942 21.4992 89.5969 21.4992 89.5969C21.4938 89.5763 21.4911 89.5659 21.4911 89.5659L21.8742 89.1346L21.8823 89.1656L21.5302 89.5888ZM19.8054 91.4637C19.8619 91.4268 19.939 91.3845 20.0368 91.3368C20.1292 91.2685 20.2215 91.2002 20.3139 91.1318C20.5855 90.9062 20.7952 90.6968 20.9431 90.5037L21.1648 90.2139L21.349 90.0333L21.6311 89.5954C21.7844 89.4228 21.8838 89.2975 21.9295 89.2194L22.3877 88.5699L22.647 88.171C22.647 88.171 22.7612 87.9757 22.9895 87.585C23.0254 87.5535 23.0406 87.5274 23.0352 87.5068C23.0298 87.4862 23.0347 87.4628 23.0499 87.4368C23.1413 87.2805 23.1869 87.2024 23.1869 87.2024C23.2326 87.1242 23.2706 87.0591 23.3011 87.007C23.3261 86.9343 23.3539 86.8719 23.3843 86.8198C23.2605 86.8522 23.1915 86.9255 23.1773 87.0395C23.1773 87.0395 23.18 87.0498 23.1854 87.0704C23.1854 87.0704 23.1751 87.0731 23.1544 87.0785C23.1653 87.1198 23.1304 87.2392 23.0499 87.4368L22.9195 87.5702L22.7891 87.7037L22.781 87.6727L22.7597 87.8437L22.7125 87.7899L22.644 87.9072C22.6494 87.9278 22.6727 87.9327 22.714 87.9219C22.6835 87.974 22.6553 87.9924 22.6293 87.9772C22.588 87.988 22.5445 88.0325 22.4988 88.1106C22.4684 88.1627 22.4559 88.1991 22.4613 88.2197L22.4547 88.3207L22.3928 88.337C22.4134 88.3315 22.4237 88.3288 22.4237 88.3288C22.4183 88.3082 22.4156 88.2979 22.4156 88.2979C22.3896 88.2827 22.3434 88.3168 22.2771 88.4004C22.2314 88.4785 22.1934 88.5436 22.1629 88.5957C22.1379 88.6685 22.1074 88.7206 22.0716 88.752C22.0357 88.7835 22.0102 88.8122 21.995 88.8383L21.8808 89.0336L21.8189 89.0499C21.6406 89.2951 21.4874 89.4677 21.3592 89.5675C21.3027 89.6043 21.244 89.6749 21.1831 89.7791L21.1912 89.81L21.4373 89.6131C21.4427 89.6338 21.4454 89.6441 21.4454 89.6441C21.4661 89.6387 21.4764 89.636 21.4764 89.636L20.6888 90.6696C20.5661 90.79 20.4226 90.9158 20.2586 91.0471C20.0945 91.1784 19.9228 91.3226 19.7435 91.4799C19.7696 91.4952 19.7902 91.4897 19.8054 91.4637ZM21.3039 89.4827C21.4114 89.3883 21.5033 89.276 21.5794 89.1458L21.5175 89.162L21.6169 89.0367C21.6322 89.0106 21.6501 88.9949 21.6707 88.9895C21.7066 88.958 21.7218 88.932 21.7164 88.9114L21.8468 88.7779C21.8414 88.7573 21.8284 88.7497 21.8077 88.7551L21.7164 88.9114C21.6034 88.9851 21.5317 89.048 21.5012 89.1001L21.5175 89.162C21.4458 89.2249 21.379 89.2645 21.317 89.2808L21.3642 89.3345L21.5256 89.193C21.4234 89.308 21.3495 89.4046 21.3039 89.4827ZM21.9965 88.9702C21.9813 88.9963 21.953 89.0147 21.9118 89.0255L21.8808 89.0336L21.8727 89.0027L21.928 89.0874L21.9965 88.9702ZM22.6298 89.3665C22.6396 89.3198 22.6803 89.265 22.752 89.2021L22.7211 89.2102C22.7059 89.2363 22.6879 89.252 22.6673 89.2574C22.6467 89.2628 22.6314 89.2889 22.6216 89.3356L22.6298 89.3665ZM21.9884 88.9393C22.0036 88.9132 22.0215 88.8975 22.0422 88.8921C22.078 88.8606 22.1009 88.8215 22.1107 88.7749C22.1313 88.7694 22.1443 88.7771 22.1497 88.7977L22.0193 88.9311L21.9884 88.9393ZM22.0442 88.3953C22.1876 88.2695 22.2822 88.1675 22.3278 88.0893C22.3072 88.0947 22.2969 88.0974 22.2969 88.0974C22.2915 88.0768 22.2888 88.0665 22.2888 88.0665L22.0523 88.4263L21.8844 88.6688C21.8898 88.6894 21.9028 88.6971 21.9234 88.6916L22.0442 88.3953ZM23.4838 88.7125L23.4528 88.7206C23.3462 88.9029 23.293 88.9941 23.293 88.9941L23.3239 88.986L23.4838 88.7125ZM21.3566 90.6929C21.4185 90.6767 21.4571 90.6555 21.4723 90.6295C21.6256 90.457 21.7631 90.2665 21.8849 90.0581C21.9718 89.9692 22.074 89.8542 22.1913 89.7131C22.3033 89.5514 22.4104 89.413 22.5125 89.298L22.5663 89.2508L22.5958 89.1108L22.8632 88.7429L23.0377 88.3994L23.4635 87.6261L23.6837 87.2044L23.7131 87.0643L23.7963 86.8771L23.878 86.5579C23.9585 86.3604 24.0086 86.2149 24.0282 86.1215L24.012 86.0596L23.9501 86.0759L23.9207 86.2159L23.5584 87.1049C23.5181 87.2037 23.4675 87.3052 23.4066 87.4094C23.3664 87.5082 23.3261 87.6069 23.2859 87.7057C23.2554 87.7578 23.2201 87.8333 23.1798 87.932C23.1548 88.0048 23.1091 88.0829 23.0428 88.1665C23.033 88.2131 22.9922 88.2679 22.9205 88.3309L22.9596 88.3537C22.9704 88.395 22.9682 88.4286 22.953 88.4547C22.8617 88.611 22.7725 88.7336 22.6856 88.8226L22.5323 88.9951C22.5323 88.9951 22.522 88.9978 22.5014 89.0032C22.5014 89.0032 22.5041 89.0135 22.5095 89.0342L22.5795 89.0489L22.5339 89.127C22.5034 89.1791 22.4523 89.2366 22.3806 89.2995C22.3295 89.357 22.2708 89.4276 22.2045 89.5111L21.8767 90.0272C21.8615 90.0532 21.7034 90.2491 21.4023 90.6148L21.3566 90.6929ZM22.0254 89.4589L22.3075 89.021C22.2923 89.047 22.4755 88.7784 22.8571 88.2152L23.1915 87.5981C23.2273 87.5667 23.2372 87.52 23.2209 87.4581L23.4117 87.1765L23.4949 86.9892L23.5244 86.8492C23.5396 86.8231 23.5548 86.7971 23.57 86.771C23.5853 86.745 23.6005 86.7189 23.6157 86.6929L23.668 86.5138C23.6582 86.5605 23.7261 86.3993 23.8719 86.0302L23.8557 85.9683L23.8019 86.0155L23.6045 86.3981C23.5044 86.689 23.4315 86.8735 23.3858 86.9517C23.3608 87.0244 23.3129 87.1362 23.2422 87.2871C23.1922 87.4326 23.134 87.5471 23.0677 87.6306C23.0677 87.6306 22.8317 88.0344 22.3598 88.8418L21.9635 89.4751L22.0254 89.4589ZM24.0739 88.0614L24.0658 88.0305L23.7461 88.5775L23.8161 88.5922L24.0739 88.0614ZM24.2667 87.283L24.2129 87.3302C24.2238 87.3715 24.2422 87.3997 24.2682 87.415L24.2667 87.283ZM23.4219 86.7107L23.3437 86.665L23.2752 86.7822C23.2806 86.8028 23.2936 86.8105 23.3143 86.805L23.4219 86.7107ZM23.9475 87.2013L24.0536 86.975L24.0846 86.9669L23.9785 87.1932L23.9475 87.2013ZM23.1139 86.9238C23.19 86.7935 23.2835 86.6036 23.3945 86.3539C23.3945 86.3539 23.3918 86.3436 23.3863 86.323C23.3918 86.3436 23.3841 86.3566 23.3635 86.3621C23.282 86.4717 23.1857 86.6513 23.0748 86.9009L23.0829 86.9319L23.1139 86.9238ZM18.7479 89.9546C18.8251 89.9123 18.9663 89.8201 19.1717 89.6781C19.2075 89.6466 19.2434 89.6151 19.2792 89.5837C19.3357 89.5468 19.3846 89.523 19.4259 89.5121C19.6322 89.458 19.8278 89.3626 20.0125 89.226C20.1917 89.0687 20.3096 88.9716 20.3661 88.9347C20.5562 88.8187 20.6997 88.6928 20.7964 88.5572L21.2856 87.8995L21.6753 87.3673C21.6807 87.3879 21.6888 87.4188 21.6997 87.4601C21.7311 87.496 21.7316 87.54 21.7012 87.592C21.6914 87.6387 21.6712 87.6881 21.6408 87.7402C21.6256 87.7663 21.6131 87.8026 21.6032 87.8493L21.4368 88.2238C21.4987 88.2076 21.5449 88.1734 21.5753 88.1213L21.6814 87.895C21.6912 87.8483 21.714 87.8092 21.7499 87.7778C21.8064 87.7409 21.8449 87.7198 21.8656 87.7143C21.9732 87.62 22.0498 87.5337 22.0954 87.4556C22.1563 87.3514 22.2199 87.2575 22.2862 87.1739L22.407 86.8776C22.4527 86.7995 22.5005 86.6877 22.5506 86.5422C22.5756 86.4695 22.6213 86.3913 22.6876 86.3078C22.7485 86.2036 22.7654 86.0999 22.7384 85.9967L22.7693 85.9886L22.8525 85.8014L23.1169 85.1696C23.1866 84.9308 23.2671 84.7332 23.3584 84.5769C23.3683 84.5303 23.3754 84.4733 23.3798 84.4059C23.3842 84.3386 23.4146 84.2865 23.4711 84.2496L23.4549 84.1877L23.4614 84.0868L23.4843 84.0477L23.4452 84.0249C23.4344 83.9836 23.429 83.963 23.429 83.963L23.5807 83.6585L23.4112 83.7691C23.4417 83.717 23.4824 83.6622 23.5335 83.6047C23.5846 83.5472 23.6123 83.4848 23.6167 83.4175C23.6113 83.3968 23.6086 83.3865 23.6086 83.3865C23.6292 83.3811 23.6396 83.3784 23.6396 83.3784L23.6624 83.3393L23.5924 83.3246C23.5924 83.3246 23.5821 83.3273 23.5614 83.3327C23.5614 83.3327 23.5587 83.3224 23.5533 83.3018L23.5452 83.2708L23.568 83.2318C23.656 83.2307 23.6891 83.189 23.6675 83.1064C23.6675 83.1064 23.6719 83.0391 23.6807 82.9045C23.6752 82.8838 23.6725 82.8735 23.6725 82.8735L23.6791 82.7725C23.6879 82.6379 23.6913 82.4826 23.6893 82.3067C23.6906 81.9755 23.6854 81.7453 23.6736 81.6161C23.6499 81.3577 23.6142 81.1796 23.5665 81.0818C23.5557 81.0405 23.5525 80.9862 23.5569 80.9189C23.5613 80.8516 23.5244 80.7951 23.4462 80.7494L23.4381 80.7185C23.4686 80.6664 23.4708 80.6327 23.4447 80.6175C23.4187 80.6023 23.385 80.6001 23.3437 80.6109L23.0033 80.7002L23.0718 80.583L22.9789 80.6073L22.948 80.6155L22.407 80.8235C22.3864 80.8289 22.3375 80.8528 22.2604 80.8951C22.2039 80.9319 22.1442 80.9145 22.0813 80.8428L22.0503 80.8509C22.0243 80.8357 21.9933 80.8438 21.9575 80.8753C21.9162 80.8861 21.8722 80.8866 21.8255 80.8768C21.6811 80.9147 21.5654 80.9781 21.4784 81.0671L21.2633 81.2558L21.3952 81.2543C21.2159 81.4116 21.1111 81.5163 21.0806 81.5684L21.0268 81.6156C20.9615 81.7871 20.9034 81.9016 20.8523 81.9591L20.7072 82.1626L20.4301 82.3676L20.4773 82.4214L20.7396 82.2864C20.7092 82.3385 20.6836 82.3673 20.663 82.3727C20.6065 82.4095 20.5218 82.4648 20.4088 82.5386C20.311 82.5863 20.2366 82.6389 20.1855 82.6964C20.1703 82.7225 20.0986 82.7854 19.9704 82.8852C19.8574 82.9589 19.7889 83.0761 19.7649 83.2368L19.6801 83.2921C19.6388 83.3029 19.6128 83.2877 19.602 83.2464C19.5803 83.1639 19.5538 83.1047 19.5223 83.0689C19.5223 83.0689 19.512 83.0716 19.4914 83.077C19.4914 83.077 19.4887 83.0667 19.4832 83.046C19.4007 83.0677 19.3263 83.1203 19.26 83.2038C19.2143 83.282 19.1839 83.3341 19.1686 83.3601C19.1382 83.4122 19.1126 83.441 19.092 83.4464C19.0714 83.4518 19.0534 83.4675 19.0382 83.4936C19.023 83.5196 19.0181 83.543 19.0235 83.5636C19.0039 83.657 18.9843 83.7503 18.9646 83.8437C18.9396 83.9164 18.9173 83.9995 18.8977 84.0928C18.6818 85.1199 18.557 85.7371 18.5232 85.9444C18.4839 86.1312 18.4271 86.5872 18.3527 87.3124C18.3537 87.4004 18.3471 87.5014 18.3329 87.6154C18.3187 87.7294 18.3067 87.8097 18.2969 87.8564L18.3111 88.4151L18.4435 89.8029C18.4597 89.8648 18.4966 89.9213 18.5541 89.9724C18.6268 89.9974 18.6915 89.9915 18.7479 89.9546ZM24.3266 87.7636C24.3919 87.5921 24.4599 87.4309 24.5306 87.28C24.6165 87.1031 24.6921 86.9289 24.7574 86.7573L24.7264 86.7655C24.671 86.8903 24.6003 87.0412 24.5143 87.2181C24.4436 87.369 24.368 87.5432 24.2875 87.7407L24.3266 87.7636ZM24.3839 87.3515C24.4448 87.2474 24.4932 87.1795 24.5291 87.1481C24.5084 87.1535 24.4954 87.1459 24.49 87.1252C24.4335 87.1621 24.3981 87.2375 24.3839 87.3515ZM23.5426 86.4143C23.5166 86.3991 23.4932 86.3942 23.4726 86.3996C23.4672 86.379 23.4645 86.3687 23.4645 86.3687C23.4645 86.3687 23.4493 86.3947 23.4188 86.4468C23.4296 86.4881 23.4557 86.5033 23.497 86.4925L23.5426 86.4143ZM22.7241 89.4741L22.7779 89.4269L23.228 88.7464L23.2346 88.6455L23.3112 88.5592C23.3265 88.5332 23.3237 88.5228 23.3031 88.5283L23.3569 88.4811L23.3554 88.3491L23.3879 88.4729C23.4129 88.4002 23.4482 88.3248 23.4939 88.2466C23.5396 88.1685 23.5543 88.0985 23.5381 88.0366C23.5793 88.0257 23.6152 87.9943 23.6456 87.9422C23.7173 87.8793 23.7935 87.749 23.874 87.5515C23.9142 87.4527 23.9621 87.3409 24.0176 87.2161C24.0731 87.0912 24.1258 86.9561 24.1759 86.8106C24.2216 86.7325 24.2107 86.6912 24.1434 86.6868L24.1663 86.6477L24.4144 85.9541C24.5037 85.6219 24.5636 85.4298 24.594 85.3777L24.625 85.3695C24.6206 85.4369 24.5955 85.5096 24.5499 85.5877C24.6432 85.6074 24.6997 85.5705 24.7194 85.4771C24.7542 85.3577 24.7787 85.241 24.7929 85.127C24.8017 84.9924 24.8235 84.8653 24.8584 84.7459C24.877 84.5646 24.8912 84.4506 24.901 84.4039C24.8956 84.3833 24.9081 84.3469 24.9386 84.2948L24.9518 84.0929C24.9802 83.8649 24.9732 83.7123 24.931 83.6352C24.9255 83.6145 24.9332 83.6015 24.9538 83.5961C24.9984 83.43 24.992 83.3214 24.9345 83.2703C24.9541 83.177 24.9585 83.1096 24.9477 83.0684L24.8386 83.0308L24.8011 83.1399C24.8291 83.331 24.8371 83.5716 24.8249 83.8615L24.794 83.8696L24.7924 83.7377C24.762 83.7898 24.7364 83.8185 24.7158 83.8239L24.7437 83.5519C24.7535 83.5053 24.7449 83.4303 24.7178 83.3272C24.6255 83.3955 24.582 83.44 24.5874 83.4606L24.4763 83.9198C24.4837 84.1164 24.4809 84.3156 24.4677 84.5176L24.492 84.6104L24.5752 84.4232L24.5996 84.516L24.6453 84.4379C24.6561 84.4792 24.6539 84.5128 24.6387 84.5389L24.6026 84.7799C24.5776 84.8526 24.5526 84.9254 24.5275 84.9981C24.5231 85.0654 24.5084 85.1354 24.4834 85.2082C24.4638 85.3015 24.4235 85.4003 24.3626 85.5045C24.0967 86.677 23.6642 87.7609 23.0651 88.7561C23.0912 88.7713 23.1248 88.7735 23.1661 88.7627L23.1123 88.8099L23.0814 88.818C23.0401 88.8288 22.9966 88.8733 22.951 88.9514C22.8999 89.009 22.8797 89.0583 22.8906 89.0996L22.8987 89.1306L22.9149 89.1925L22.853 89.2087L22.8368 89.1468L22.7226 89.3422L22.7926 89.3569L22.7389 89.4041L22.7241 89.4741L22.646 89.4284L22.5628 89.6157L22.5937 89.6075C22.6144 89.6021 22.6247 89.5994 22.6247 89.5994C22.6399 89.5734 22.6578 89.5577 22.6785 89.5522L22.6638 89.6223L22.6947 89.6141L22.7241 89.4741ZM23.5441 88.5643L23.7349 88.2827C23.7502 88.2566 23.7703 88.2072 23.7953 88.1345C23.8356 88.0357 23.8867 87.9782 23.9486 87.962C23.9692 87.9566 23.9768 87.9435 23.9714 87.9229C23.9866 87.8969 24.0045 87.8811 24.0252 87.8757L24.0171 87.8448L23.9323 87.9001C23.9323 87.9001 23.922 87.9028 23.9014 87.9082C23.9014 87.9082 23.8987 87.8979 23.8933 87.8772C23.9443 87.8197 24.0232 87.6998 24.1297 87.5175L24.1378 87.5484L24.0089 87.8138L24.079 87.8285L24.2682 87.415C24.2628 87.3943 24.2574 87.3737 24.252 87.3531C24.2618 87.3064 24.2819 87.257 24.3124 87.2049C24.3124 87.2049 24.3733 87.1007 24.4951 86.8923C24.5702 86.6741 24.6077 86.565 24.6077 86.565L24.8036 86.0505L24.8558 85.8714L24.7402 85.9348L24.8822 85.4675L24.9604 85.5131C25.0399 85.2276 25.1042 84.9682 25.1532 84.7348C25.2023 84.5013 25.2464 84.2913 25.2856 84.1045C25.2802 84.0839 25.2672 84.0763 25.2466 84.0817C25.2574 84.123 25.2422 84.149 25.2009 84.1598L25.1994 84.0279L25.3313 84.0264L25.2369 83.9188L25.2451 83.9498L25.1963 83.764C25.1811 83.7901 25.1659 83.8161 25.1507 83.8422C25.1507 83.8422 25.1534 83.8525 25.1588 83.8731L25.0263 84.5034L24.7599 85.6319L24.7386 85.8029L24.5869 86.1073L24.2784 86.9492C24.2381 87.0479 24.1952 87.1364 24.1495 87.2145C24.1038 87.2927 24.0685 87.3681 24.0435 87.4408L23.6877 88.2289L23.5132 88.5724L23.5441 88.5643ZM24.2053 86.6706C24.2466 86.6598 24.2645 86.644 24.2591 86.6234L24.5676 85.7816L24.5839 85.8435L24.6443 85.6953L24.659 85.6253L24.5661 85.6496L24.5123 85.6968L24.4976 85.7669C24.4682 85.9069 24.3784 86.1951 24.2282 86.6315C24.2282 86.6315 24.2309 86.6418 24.2363 86.6625C24.2363 86.6625 24.226 86.6652 24.2053 86.6706ZM20.1485 84.1948C20.1031 83.8538 20.0795 83.5954 20.0774 83.4195C20.0818 83.3522 20.1123 83.3001 20.1688 83.2632L20.3058 83.0288C20.2144 83.1851 20.1698 83.3512 20.1718 83.5271C20.1945 83.6976 20.2063 83.8268 20.2073 83.9147C20.1985 84.0494 20.2023 84.1476 20.2185 84.2095L20.1647 84.2567L20.1485 84.1948ZM19.2975 83.0947C19.3182 83.0893 19.3258 83.0763 19.3204 83.0557L19.2194 83.0491C19.2194 83.0491 19.2091 83.0518 19.1884 83.0572C19.1884 83.0572 19.1911 83.0675 19.1965 83.0881C19.2226 83.1034 19.2563 83.1056 19.2975 83.0947ZM19.3711 82.7446C19.3711 82.7446 19.3608 82.7473 19.3401 82.7527C19.3401 82.7527 19.3374 82.7424 19.332 82.7218L19.2422 83.01L19.3122 83.0247L19.3711 82.7446ZM23.9425 85.4162L23.9034 85.3934C23.8838 85.4868 23.8767 85.5438 23.8821 85.5644L23.9425 85.4162ZM23.7065 85.1473L23.6756 85.1554L23.5614 85.3508C23.5668 85.3714 23.5695 85.3817 23.5695 85.3817C23.5902 85.3763 23.6005 85.3736 23.6005 85.3736L23.7065 85.1473ZM23.5903 85.8394L23.6685 85.8851L23.6522 85.8232C23.6827 85.7711 23.6979 85.745 23.6979 85.745L23.773 85.5268L23.8613 85.1067C23.9408 84.8212 23.9854 84.6551 23.9953 84.6084L23.4909 85.9647C23.4963 85.9854 23.499 85.9957 23.499 85.9957C23.5196 85.9903 23.5299 85.9876 23.5299 85.9876L23.5903 85.8394ZM24.2307 85.506C24.2253 85.4854 24.2123 85.4778 24.1916 85.4832L24.1312 85.6314L24.1622 85.6232L24.2307 85.506ZM19.4624 82.5883C19.4624 82.5883 19.457 82.5677 19.4462 82.5264L19.3924 82.5736C19.3978 82.5942 19.3853 82.6306 19.3549 82.6827C19.3755 82.6773 19.3885 82.6849 19.3939 82.7055L19.4624 82.5883ZM18.883 82.1448L18.9139 82.1367L18.8439 82.122L18.6287 82.3108L18.6678 82.3336L18.883 82.1448ZM24.8868 85.8633C24.9118 85.7905 24.9189 85.7335 24.9081 85.6923C24.8973 85.651 24.8995 85.6173 24.9147 85.5913L24.9066 85.5603L24.8756 85.5685C24.8919 85.6304 24.8951 85.6847 24.8853 85.7313C24.8701 85.7574 24.8575 85.7937 24.8477 85.8404C24.8684 85.835 24.8814 85.8426 24.8868 85.8633ZM25.3232 86.0135C25.3384 85.9874 25.3536 85.9614 25.3689 85.9353C25.3841 85.9093 25.389 85.8859 25.3836 85.8653L25.413 85.7252C25.413 85.7252 25.4027 85.728 25.382 85.7334C25.382 85.7334 25.3793 85.723 25.3739 85.7024L25.2841 85.9906C25.3047 85.9852 25.3178 85.9928 25.3232 86.0135ZM24.7493 86.7264C24.8613 86.5647 24.9249 86.4708 24.9401 86.4448L25.0005 86.2966L25.0314 86.2885C25.0456 86.1745 25.0979 85.9954 25.1882 85.7511C25.2034 85.7251 25.2056 85.6914 25.1948 85.6501L25.2308 85.4091C25.2254 85.3885 25.2254 85.3885 25.2308 85.4091C25.2515 85.4037 25.2591 85.3907 25.2537 85.37L25.3384 85.3147C25.333 85.2941 25.3249 85.2632 25.3141 85.2219C25.3185 85.1546 25.3332 85.0845 25.3582 85.0118L25.4089 84.7008L25.479 84.7155C25.4996 84.7101 25.5251 84.6813 25.5556 84.6292C25.4829 84.6042 25.4465 84.5917 25.4465 84.5917C25.4465 84.5917 25.4438 84.5813 25.4384 84.5607C25.4536 84.5347 25.4585 84.5113 25.4531 84.4907L25.3912 84.5069L25.4089 84.7008L25.3242 84.7561C25.309 84.7821 25.3068 84.8158 25.3176 84.857C25.323 84.8777 25.3181 84.901 25.3029 84.9271C25.2941 85.0617 25.2772 85.1654 25.2521 85.2381C25.0857 85.6126 24.9731 85.9399 24.9142 86.22L24.7412 86.6954L24.7493 86.7264ZM19.7085 82.3914C19.7031 82.3708 19.7004 82.3605 19.7004 82.3605C19.7211 82.3551 19.7314 82.3524 19.7314 82.3524L19.8065 82.1342L19.7984 82.1032C19.7375 82.2074 19.7021 82.2828 19.6923 82.3295C19.6923 82.3295 19.6977 82.3502 19.7085 82.3914ZM24.1282 85.3675C24.1076 85.3729 24.0972 85.3756 24.0972 85.3756C24.0918 85.355 24.0891 85.3447 24.0891 85.3447L24.1201 85.3366L24.1937 84.9864L24.321 84.5891L24.3048 84.5272C24.32 84.5012 24.3195 84.4572 24.3033 84.3953L24.3474 84.1852C24.317 84.2373 24.2767 84.3361 24.2266 84.4815C24.2321 84.5022 24.2141 84.5179 24.1729 84.5287L24.1028 84.514C24.1647 84.4978 24.193 84.4793 24.1876 84.4587C24.2028 84.4327 24.205 84.399 24.1942 84.3577L24.1175 84.444L24.1028 84.514L23.9932 85.1052L24.0404 85.159L24.0714 85.1508C24.0822 85.1921 24.08 85.2258 24.0648 85.2518L24.0044 85.4L24.0435 85.4228L24.1282 85.3675ZM25.3739 85.7024C25.4967 85.582 25.5316 85.4626 25.4785 85.3442C25.4534 85.4169 25.436 85.4766 25.4262 85.5233C25.4164 85.57 25.399 85.6297 25.3739 85.7024ZM19.2366 81.8536C19.1845 81.8231 19.1585 81.8079 19.1585 81.8079L19.1128 81.886C19.1128 81.886 19.1155 81.8964 19.1209 81.917C19.1209 81.917 19.1313 81.9143 19.1519 81.9089L19.2366 81.8536ZM25.2247 84.8814L25.1725 85.0605C25.1931 85.0551 25.2061 85.0627 25.2116 85.0834L25.2247 84.8814ZM19.4259 81.44C19.364 81.4563 19.3151 81.4801 19.2793 81.5116L19.3183 81.5344L19.4259 81.44ZM19.6263 81.3213L19.6182 81.2903L19.4878 81.4238L19.6263 81.3213ZM25.3212 84.4922L25.2821 84.4694L25.2298 84.6485L25.2917 84.6323L25.3212 84.4922ZM19.468 81.7267C19.5201 81.7572 19.5538 81.7594 19.569 81.7333C19.5842 81.7073 19.5994 81.6812 19.6147 81.6552C19.6559 81.6443 19.6842 81.6259 19.6994 81.5999C19.7146 81.5738 19.7222 81.5608 19.7222 81.5608C19.7743 81.5912 19.808 81.5934 19.8232 81.5674C19.833 81.5207 19.8455 81.4843 19.8608 81.4583L19.9212 81.3101L19.9912 81.3248C19.9858 81.3042 19.9831 81.2939 19.9831 81.2939C20.0037 81.2885 20.014 81.2858 20.014 81.2858C20.127 81.212 20.1835 81.1751 20.1835 81.1751C20.24 81.1383 20.2758 81.1068 20.2911 81.0808C20.3215 81.0287 20.3443 80.9896 20.3596 80.9635L20.4281 80.8463L20.42 80.8154L20.389 80.8235C20.3325 80.8604 20.2787 80.9076 20.2276 80.9651C20.1972 81.0172 20.1537 81.0616 20.0972 81.0985C20.0353 81.1148 19.9891 81.1489 19.9587 81.201C19.9381 81.2064 19.9174 81.2118 19.8968 81.2173C19.8914 81.1966 19.8811 81.1993 19.8658 81.2254L19.7583 81.3198L19.7045 81.3669L19.504 81.4857C19.4834 81.4911 19.4552 81.5095 19.4193 81.541C19.3835 81.5725 19.3916 81.6034 19.4437 81.6339L19.2432 81.7526L19.2514 81.7835C19.2926 81.7727 19.3339 81.7619 19.3752 81.7511C19.411 81.7196 19.442 81.7115 19.468 81.7267ZM25.546 84.4663L25.5607 84.3963L25.4287 84.3978C25.4287 84.3978 25.4314 84.4081 25.4369 84.4288C25.4369 84.4288 25.4265 84.4315 25.4059 84.4369L25.445 84.4597C25.4971 84.4902 25.5334 84.5027 25.5541 84.4973L25.546 84.4663ZM24.113 84.0482C24.1641 83.9907 24.2146 83.8892 24.2647 83.7437C24.2941 83.6037 24.3034 83.513 24.2926 83.4718C24.297 83.4044 24.2574 83.3376 24.1739 83.2713L24.1099 83.7843L24.0592 84.0954L24.113 84.0482ZM24.0237 83.7077C24.0541 83.6556 24.0693 83.6296 24.0693 83.6296L24.0059 83.5139C24.0526 83.5237 24.0732 83.5183 24.0678 83.4976C24.083 83.4716 24.0983 83.4455 24.1135 83.4195C24.0929 83.4249 24.0825 83.4276 24.0825 83.4276C24.0771 83.407 24.0744 83.3967 24.0744 83.3967C24.044 83.4488 24.0184 83.4775 23.9978 83.4829L24.0059 83.5139C23.9907 83.5399 23.9912 83.5839 24.0074 83.6458L24.0237 83.7077ZM24.7173 83.9559L24.763 83.8777L24.8574 83.9853L24.8345 84.0244L24.7173 83.9559ZM24.4783 83.4231C24.5088 83.371 24.5284 83.2776 24.5372 83.143C24.4807 83.1798 24.435 83.258 24.4002 83.3774L24.4474 83.4312L24.4783 83.4231ZM25.5363 84.3034C25.5874 84.2459 25.5662 84.2074 25.4729 84.1877L25.5348 84.1715C25.5761 84.1607 25.5994 84.1656 25.6048 84.1862L25.6033 84.0543L25.5561 84.0005C25.5507 83.9799 25.5686 83.9641 25.6099 83.9533C25.6305 83.9479 25.6381 83.9349 25.6327 83.9142C25.6479 83.8882 25.6474 83.8442 25.6312 83.7823C25.6204 83.741 25.6019 83.7128 25.5759 83.6976C25.6997 83.6651 25.6987 83.5771 25.5728 83.4337L25.5759 83.6976L25.5251 84.0086L25.5561 84.0005C25.5365 84.0939 25.5087 84.1563 25.4729 84.1877C25.4989 84.203 25.5201 84.2415 25.5363 84.3034ZM25.3937 83.3814L25.3628 83.3896L25.2598 83.8797L25.3298 83.8945L25.3937 83.3814ZM23.5345 82.3473C23.4716 82.2756 23.4581 82.224 23.4939 82.1925C23.5244 82.1404 23.5472 82.1014 23.5624 82.0753L23.5345 82.3473ZM25.3856 83.3505C25.3944 83.2159 25.4059 83.0915 25.4201 82.9775C25.3484 83.0405 25.3152 83.0822 25.3207 83.1029L25.3531 83.2267C25.364 83.268 25.3618 83.3016 25.3465 83.3277C25.3672 83.3222 25.3802 83.3299 25.3856 83.3505ZM25.7114 83.3312L25.7246 83.1293L25.7053 82.8035L25.6743 82.8116L25.6038 83.4256L25.6429 83.4484L25.7114 83.3312ZM25.1532 82.7167C25.1326 82.7221 25.1196 82.7145 25.1141 82.6939L25.0538 82.8421C25.0744 82.8366 25.0874 82.8443 25.0928 82.8649L25.1532 82.7167ZM24.9528 82.8355C24.9528 82.8355 24.9555 82.8458 24.9609 82.8664C24.9609 82.8664 24.9712 82.8637 24.9919 82.8583L25.0066 82.7883L24.8665 82.7588L24.9203 82.7116L24.9513 82.7035L25.0132 82.6873C24.9719 82.6981 24.9458 82.6829 24.935 82.6416C24.9242 82.6003 24.9286 82.533 24.9482 82.4397L24.8538 82.3321C24.8332 82.3375 24.8153 82.3532 24.8 82.3793C24.7848 82.4053 24.7799 82.4287 24.7853 82.4493L24.7965 82.7441L24.8762 82.9217L24.9528 82.8355ZM21.3161 80.448C21.378 80.4318 21.4345 80.3949 21.4856 80.3374C21.5366 80.2799 21.5644 80.2175 21.5688 80.1501C21.5123 80.187 21.4482 80.2369 21.3765 80.2998C21.3254 80.3573 21.2716 80.4045 21.2151 80.4414L21.3161 80.448ZM20.1637 79.46L20.1556 79.4291L20.1165 79.4063L19.9942 79.5707L20.0023 79.6016L20.1637 79.46ZM24.9614 82.2377C24.956 82.2171 24.9636 82.2041 24.9842 82.1986L24.8442 82.1692L24.8051 82.1464L24.8346 82.0063C24.8346 82.0063 24.8291 81.9857 24.8183 81.9444L24.7726 82.0226L24.7823 82.1854C24.7931 82.2267 24.7909 82.2604 24.7757 82.2864L24.9223 82.2149L24.9614 82.2377ZM20.387 79.3022L20.2469 79.2728C20.2263 79.2782 20.2008 79.307 20.1703 79.3591C20.2224 79.3895 20.2485 79.4047 20.2485 79.4047L20.387 79.3022ZM25.3242 82.738L25.3633 82.7609L25.3795 82.8228L25.4105 82.8147C25.3942 82.7527 25.3959 82.6751 25.4156 82.5817L25.3846 82.5899C25.3846 82.5899 25.377 82.6029 25.3618 82.6289C25.3672 82.6496 25.3726 82.6702 25.378 82.6908C25.3726 82.6702 25.3596 82.6626 25.3389 82.668C25.3163 82.4975 25.2958 82.2934 25.2775 82.0555C25.2799 81.8123 25.2491 81.6109 25.1852 81.4512L25.2801 82.9481L25.3191 82.9709L25.3242 82.738ZM24.8183 81.9444C24.8129 81.9238 24.8075 81.9031 24.8021 81.8825C24.8173 81.8565 24.8249 81.8434 24.8249 81.8434C24.7989 81.8282 24.7652 81.826 24.7239 81.8368L24.8183 81.9444ZM25.6941 82.5087L25.6698 82.4158C25.6427 82.3126 25.6314 82.2274 25.6358 82.1601L25.6048 82.1682L25.6632 82.5168L25.7022 82.5396L25.6941 82.5087ZM25.546 82.4483C25.5439 82.2724 25.5321 82.1432 25.5104 82.0606L25.4795 82.0687L25.4841 82.4645L25.5231 82.4874L25.546 82.4483ZM21.7662 79.7676L21.6733 79.7919L21.6505 79.831C21.7124 79.8147 21.746 79.8169 21.7514 79.8376L21.7662 79.7676ZM23.8304 81.0787L23.7735 80.8621L23.7426 80.8702L23.7116 80.8783L23.7279 80.9402C23.7441 81.0021 23.7652 81.0407 23.7913 81.0559L23.8075 81.1178L23.8304 81.0787ZM25.6246 81.8653L25.6003 81.7724L25.5693 81.7805L25.5627 81.8815L25.6099 81.9353L25.6246 81.8653ZM20.4098 79.2632C20.4815 79.2002 20.5326 79.1427 20.5631 79.0906C20.5989 79.0592 20.6348 79.0277 20.6706 78.9963C20.7065 78.9648 20.7554 78.9409 20.8173 78.9247C20.8379 78.9193 20.8689 78.9112 20.9101 78.9004C20.946 78.8689 20.9585 78.8325 20.9477 78.7913L21.0081 78.6431C21.0287 78.6377 21.0363 78.6247 21.0309 78.604C21.0515 78.5986 21.0619 78.5959 21.0619 78.5959C21.0564 78.5753 21.0537 78.5649 21.0537 78.5649L21.0228 78.5731C20.9869 78.6045 20.9408 78.6387 20.8843 78.6756C20.843 78.6864 20.8202 78.7255 20.8158 78.7928C20.8114 78.8601 20.7423 78.9333 20.6087 79.0125L20.3007 79.2256C20.3528 79.2561 20.3892 79.2686 20.4098 79.2632ZM24.7016 81.2472C24.6854 81.1853 24.6876 81.1516 24.7082 81.1462L24.692 81.0843C24.6866 81.0637 24.6735 81.0561 24.6529 81.0615L24.6153 81.1706C24.6208 81.1912 24.6495 81.2168 24.7016 81.2472ZM25.5921 81.7415C25.6128 81.736 25.6204 81.723 25.615 81.7024L25.581 81.4466C25.5397 81.4575 25.5196 81.5069 25.5206 81.5948C25.5162 81.6621 25.5297 81.7137 25.5612 81.7496L25.5921 81.7415ZM22.1295 79.6392C22.1393 79.5925 22.1334 79.5279 22.1117 79.4453L22.0808 79.4535L22.0676 79.6554L22.1295 79.6392ZM21.825 79.4875C21.825 79.4875 21.8457 79.482 21.8869 79.4712L21.9717 79.4159C21.9869 79.3899 22.0151 79.3714 22.0564 79.3606L22.0402 79.2987L21.8088 79.4255L21.8169 79.4565C21.8017 79.4825 21.7941 79.4956 21.7941 79.4956C21.8147 79.4902 21.825 79.4875 21.825 79.4875ZM25.175 81.917C25.1514 81.6586 25.1385 81.4414 25.1365 81.2655L25.1771 81.4202L25.208 81.4121L25.1725 81.0245C25.1312 81.0353 25.103 81.0537 25.0878 81.0798L25.0796 81.0488C25.1568 81.0065 25.1612 80.9392 25.0928 80.8469C25.0874 80.8262 25.0717 80.8083 25.0456 80.7931C25.0196 80.7778 24.9936 80.7626 24.9675 80.7474C24.9459 80.6649 24.9193 80.6057 24.8878 80.5698L25.1441 81.9251L25.175 81.917ZM21.6769 79.4271C21.6921 79.401 21.7535 79.3408 21.8611 79.2464C21.8763 79.2204 21.9175 79.2096 21.9849 79.2139C22.0674 79.1923 22.1239 79.1554 22.1543 79.1033C22.2782 79.0709 22.2983 79.0215 22.2147 78.9552C22.1941 78.9606 22.1631 78.9687 22.1219 78.9795C22.0958 78.9643 22.0752 78.9697 22.06 78.9958C21.7721 79.1595 21.5896 79.2625 21.5124 79.3048L21.4815 79.3129L21.4896 79.3438C21.5157 79.3591 21.539 79.364 21.5596 79.3586C21.6009 79.3477 21.6243 79.3526 21.6297 79.3733L21.6215 79.3423C21.6063 79.3684 21.6041 79.402 21.6149 79.4433L21.6769 79.4271ZM24.6138 81.0387C24.6443 80.9866 24.6595 80.9605 24.6595 80.9605C24.6693 80.9138 24.6585 80.8726 24.627 80.8367C24.6162 80.7954 24.6157 80.7515 24.6255 80.7048C24.6147 80.6635 24.5908 80.6146 24.554 80.5581C24.5117 80.481 24.5057 80.4164 24.5362 80.3643L24.4109 80.2648L24.3799 80.273C24.293 80.3619 24.3016 80.4369 24.4058 80.4977L24.5164 80.6672L24.5017 80.7373L24.5666 80.9849L24.6138 81.0387ZM21.4023 78.5066L21.3861 78.4447L21.1009 78.6187L21.1481 78.6725L21.4023 78.5066ZM22.9505 79.49C23.0895 79.4315 23.2204 79.342 23.3432 79.2216L23.2113 79.2231L23.226 79.1531L23.0941 79.1546C23.0941 79.1546 23.0811 79.147 23.055 79.1318C23.0496 79.1111 23.0366 79.1035 23.016 79.1089C22.9953 79.1143 22.9437 79.1279 22.8612 79.1495C22.7786 79.1712 22.7222 79.208 22.6917 79.2601C22.6701 79.1776 22.618 79.1471 22.5354 79.1688C22.4735 79.185 22.4192 79.1882 22.3725 79.1784L22.4882 79.115C22.4155 79.09 22.3406 79.0986 22.2634 79.1409C22.1809 79.1625 22.1244 79.1994 22.094 79.2515C22.1048 79.2928 22.1205 79.3107 22.1411 79.3053L22.265 79.2728C22.291 79.288 22.335 79.2875 22.3969 79.2713L22.4065 79.4342L22.265 79.2728L22.2208 79.4829C22.2262 79.5035 22.2137 79.5399 22.1833 79.592L22.1914 79.6229L22.2452 79.5757C22.3233 79.6214 22.3803 79.6285 22.4162 79.5971C22.6019 79.5483 22.7333 79.5028 22.8104 79.4606L22.9424 79.459L22.9505 79.49ZM22.6968 79.0272L22.6039 79.0516L22.7211 79.1201L22.6968 79.0272ZM25.3323 80.751C25.353 80.7455 25.3606 80.7325 25.3552 80.7119L25.2755 80.5343L25.2446 80.5424L25.3323 80.751ZM21.4952 78.4822C21.5571 78.466 21.6033 78.4318 21.6337 78.3797L21.6256 78.3488L21.4952 78.4822ZM21.5312 78.2412L21.4612 78.2265L21.4399 78.3975L21.479 78.4203L21.5312 78.2412ZM24.727 80.0827L24.6082 79.8822C24.6137 79.9029 24.606 79.9159 24.5854 79.9213L24.6651 80.0989L24.727 80.0827ZM30.2605 92.8236C30.2084 92.7932 30.1151 92.7736 29.9804 92.7648C29.9706 92.8115 29.9397 92.8196 29.8876 92.7891C29.7323 92.7858 29.6335 92.7455 29.5912 92.6684L29.4497 92.507L29.3553 92.3994L29.339 92.3375C29.3282 92.2963 29.3098 92.268 29.2837 92.2528L29.2528 92.2609C29.2474 92.2403 29.2132 92.1941 29.1503 92.1224C29.1449 92.1017 29.1264 92.0735 29.095 92.0376C29.0896 92.017 29.0891 91.973 29.0935 91.9057C29.1087 91.8797 29.0821 91.8205 29.0138 91.7281C28.9823 91.6922 28.9514 91.7004 28.9209 91.7525L28.9291 91.7834C28.9084 91.7888 28.8954 91.7812 28.89 91.7606C28.8575 91.6368 28.8228 91.5466 28.786 91.4901C28.7805 91.4695 28.7518 91.4439 28.6997 91.4135L28.6835 91.3516L28.7225 91.3744L28.7535 91.3663C28.7372 91.3044 28.7188 91.2762 28.6982 91.2816C28.6775 91.287 28.6645 91.2794 28.6591 91.2587C28.6429 91.1968 28.6424 91.1529 28.6576 91.1268C28.6522 91.1062 28.6441 91.0752 28.6332 91.0339L28.6251 91.003L28.6023 91.0421L28.6185 91.104L28.5876 91.1121C28.5615 91.0969 28.5404 91.0583 28.5241 90.9964C28.4927 90.9605 28.4846 90.9296 28.4998 90.9035C28.4944 90.8829 28.4889 90.8623 28.4835 90.8416L28.5145 90.8335C28.5449 90.7814 28.5575 90.7451 28.552 90.7244C28.5466 90.7038 28.5179 90.6782 28.4658 90.6478C28.4343 90.6119 28.4078 90.5527 28.3861 90.4702C28.3645 90.3877 28.3607 90.2894 28.375 90.1754C28.3685 90.0668 28.3599 89.9919 28.3491 89.9506C28.3589 89.9039 28.366 89.8469 28.3704 89.7796C28.3748 89.7123 28.3895 89.6422 28.4145 89.5695C28.4233 89.4349 28.425 89.3572 28.4196 89.3366L28.4115 89.3057C28.4115 89.3057 28.4012 89.3084 28.3805 89.3138C28.3805 89.3138 28.3832 89.3241 28.3887 89.3447L28.3526 89.5858C28.333 89.6791 28.3286 89.7464 28.3394 89.7877L28.2856 89.8349L28.2694 89.773C28.2586 89.7317 28.263 89.6644 28.2826 89.571C28.2664 89.5091 28.2681 89.4315 28.2877 89.3381C28.2867 89.2502 28.2884 89.1725 28.2928 89.1052C28.2971 89.0379 28.3015 88.9706 28.3059 88.9033L28.3257 88.6003C28.3464 88.5949 28.3464 88.5949 28.3257 88.6003C28.3203 88.5797 28.3176 88.5694 28.3176 88.5694L28.3014 88.5075C28.2906 88.4662 28.295 88.3989 28.3146 88.3055L28.3065 88.2746L28.2755 88.2827L28.2608 88.3527L28.238 88.3918L28.2298 88.3608C28.2298 88.3608 28.2195 88.3635 28.1989 88.3689C28.1989 88.3689 28.1962 88.3586 28.1908 88.338L28.1989 88.3689L28.1547 88.579L28.1319 88.6181L28.1238 88.5871C28.1021 88.5046 28.0962 88.44 28.106 88.3933C28.0898 88.3314 28.0893 88.2874 28.1045 88.2614C28.1143 88.2147 28.1241 88.168 28.1339 88.1213L28.0852 87.9356L28.0543 87.9437C28.0336 87.9491 28.026 87.9622 28.0314 87.9828L27.9776 88.03C27.9776 88.03 27.9673 88.0327 27.9467 88.0381C27.9413 88.0175 27.9489 88.0044 27.9695 87.999C27.9479 87.9165 27.955 87.8595 27.9908 87.828L27.9827 87.7971C27.9817 87.7091 27.9883 87.6081 28.0025 87.4941C28.0167 87.3801 28.0287 87.2998 28.0385 87.2531C28.0582 87.1598 28.0626 87.0924 28.0517 87.0512C28.067 87.0251 28.0643 87.0148 28.0436 87.0202C28.0382 86.9996 28.0328 86.9789 28.0274 86.9583C27.9861 86.9691 27.9682 86.9849 27.9736 87.0055C27.9736 87.0055 27.9584 87.0315 27.9279 87.0836L27.9036 86.9908L27.933 86.8507L27.9249 86.8198L27.8939 86.8279C27.9048 86.8692 27.8949 86.9158 27.8645 86.9679L27.8726 86.9989C27.8672 86.9783 27.8542 86.9706 27.8335 86.9761L27.832 86.8441L27.8239 86.8132C27.8033 86.8186 27.7957 86.8316 27.8011 86.8522C27.7706 86.9043 27.7635 86.9613 27.7798 87.0233C27.7591 87.0287 27.7515 87.0417 27.7569 87.0623L27.8188 87.0461C27.8188 87.0461 27.8215 87.0564 27.8269 87.077C27.8269 87.077 27.8373 87.0743 27.8579 87.0689C27.8373 87.0743 27.8297 87.0874 27.8351 87.108C27.7677 87.1036 27.7449 87.1427 27.7666 87.2252L27.6245 87.6925L27.6164 87.6616L27.6443 87.3896C27.6781 87.1822 27.7016 86.9776 27.7148 86.7756L27.7869 86.2936L27.8016 86.2235C27.7603 86.2344 27.7424 86.2501 27.7478 86.2707L27.7036 86.4808L27.6889 86.5508C27.6781 86.5096 27.683 86.4862 27.7036 86.4808L27.8117 85.7577C27.8662 85.545 27.9218 85.2106 27.9787 84.7546L28.0736 84.2334C28.0976 84.0727 28.1292 83.899 28.1685 83.7123C28.2023 83.5049 28.2231 83.29 28.2309 83.0674C28.219 82.9381 28.2229 82.8268 28.2425 82.7335C28.2622 82.6401 28.2742 82.5598 28.2786 82.4925C28.3266 82.1711 28.3523 81.9328 28.3557 81.7775L28.4313 80.9306L28.5018 80.3166C28.5194 80.0473 28.5223 79.8481 28.5105 79.7189L28.5627 79.5397C28.6054 79.1977 28.6279 78.9051 28.6302 78.6619C28.6292 78.5739 28.6483 78.4366 28.6876 78.2499L28.6673 77.1635L28.7622 76.6423L28.782 76.3394L28.8261 76.1293L28.8718 76.0512C28.8555 75.9893 28.8518 75.891 28.8606 75.7564L28.9733 75.4291C28.9885 75.403 28.9907 75.3694 28.9799 75.3281C29.0103 75.276 29.0359 75.2473 29.0565 75.2419C29.1184 75.2256 29.1852 75.186 29.2569 75.1231L29.2488 75.0922C29.2532 75.0248 29.2419 74.9396 29.2148 74.8364C29.1986 74.7745 29.2366 74.7094 29.329 74.6411C29.3702 74.6302 29.3985 74.6118 29.4137 74.5858C29.4289 74.5597 29.4442 74.5337 29.4594 74.5076C29.454 74.487 29.4665 74.4506 29.4969 74.3985C29.4915 74.3779 29.4991 74.3649 29.5198 74.3594L29.4954 74.2666L29.5492 74.2194L29.5264 74.2585L29.5736 74.3123C29.5942 74.3068 29.6045 74.3041 29.6045 74.3041C29.5991 74.2835 29.5964 74.2732 29.5964 74.2732C29.6377 74.2624 29.661 74.2673 29.6664 74.2879L29.6974 74.2798L29.7283 74.2717L29.7364 74.3026L29.6842 74.4817L29.7085 74.5746L29.7232 74.5046C29.7178 74.4839 29.7613 74.4394 29.8537 74.3711C29.8743 74.3657 29.9156 74.3549 29.9775 74.3386C30.0546 74.2964 30.1057 74.2388 30.1307 74.1661L30.1535 74.127L30.2007 74.1808C30.2116 74.2221 30.23 74.2503 30.256 74.2656C30.2865 74.2135 30.3017 74.1874 30.3017 74.1874C30.3169 74.1614 30.3621 74.0393 30.4372 73.8211C30.5089 73.7581 30.5497 73.7033 30.5595 73.6567C30.5595 73.6567 30.5698 73.654 30.5904 73.6485C30.6111 73.6431 30.6241 73.6507 30.6295 73.6714C30.6664 73.7279 30.7207 73.7247 30.7924 73.6617C30.787 73.6411 30.7946 73.6281 30.8152 73.6227L30.8005 73.6927C30.8059 73.7133 30.801 73.7367 30.7858 73.7627C30.7706 73.7888 30.776 73.8094 30.802 73.8246C30.8281 73.8398 30.8721 73.8393 30.934 73.8231C31.0165 73.8015 31.0366 73.7521 30.9944 73.6749C30.9835 73.6337 30.9987 73.6076 31.04 73.5968C31.1019 73.5806 31.1481 73.5464 31.1785 73.4943C31.2144 73.4628 31.2633 73.439 31.3252 73.4227C31.3871 73.4065 31.4414 73.4033 31.4881 73.4131C31.4881 73.4131 31.5141 73.4283 31.5662 73.4588C31.5977 73.4946 31.6009 73.5489 31.5759 73.6217C31.566 73.6683 31.5639 73.702 31.5693 73.7226C31.5801 73.7639 31.5958 73.7818 31.6165 73.7764L31.6246 73.8074L31.5251 73.9327L31.5414 73.9946C31.6662 74.0501 31.7584 74.1913 31.8179 74.4183L31.8828 74.6659C31.9261 74.831 31.9444 75.0688 31.9376 75.3794C31.9549 75.5292 32.0014 75.7486 32.0772 76.0375L32.1259 76.2232C32.1908 76.4709 32.2922 76.731 32.4298 77.0036C32.509 77.1373 32.6125 77.3638 32.7404 77.6831C32.7827 77.7602 32.8043 77.8428 32.8053 77.9307C32.827 78.0133 32.859 78.0931 32.9012 78.1702C32.9283 78.2734 32.9895 78.4228 33.0849 78.6183C33.1813 78.9018 33.3276 79.2493 33.5238 79.661L33.8669 80.4643L34.1302 81.09C34.2473 81.368 34.3274 81.5896 34.3707 81.7547C34.4986 82.074 34.5842 82.3162 34.6275 82.4813C34.6329 82.502 34.6459 82.5096 34.6666 82.5042C34.699 82.628 34.763 82.7876 34.8584 82.9832L34.9609 83.1217C35.0184 83.1728 35.1029 83.327 35.2146 83.5845C35.2254 83.6257 35.2416 83.6876 35.2633 83.7702C35.3002 83.8267 35.3061 83.8913 35.281 83.964L35.3282 84.0178L35.382 83.9706L35.4394 83.5586L35.5342 83.0375L35.6307 82.6483L35.6895 82.3682L35.8169 81.9709L35.8905 81.6207L35.9184 81.3487C35.9282 81.3021 35.95 81.175 35.9838 80.9677L36.1 80.2755C36.1044 80.2082 36.1115 80.1512 36.1213 80.1045C36.1257 80.0372 36.1329 79.9802 36.1427 79.9335L36.1934 79.6225L36.3162 78.8294L36.3426 78.4255L36.4588 77.7333L36.5603 77.1112L36.6603 76.3572L36.8434 75.4159C36.8576 75.3019 36.8746 75.1982 36.8942 75.1049C36.9344 75.0061 36.9568 74.9231 36.9612 74.8557C37.0058 74.6896 37.0522 74.4459 37.1002 74.1245L37.2164 73.4324L37.2849 73.3152L37.2783 73.4162L37.2291 73.8592L37.2144 73.9292C37.1633 73.9867 37.1388 74.1034 37.1408 74.2793C37.1462 74.2999 37.1391 74.3569 37.1195 74.4503C37.1205 74.5383 37.1014 74.6756 37.0621 74.8623C37.0425 74.9557 37.0175 75.0284 36.987 75.0805C36.987 75.0805 36.9897 75.0908 36.9952 75.1115C36.9952 75.1115 37.0055 75.1088 37.0261 75.1034L37.0571 75.0952L37.0621 74.8623L37.0946 74.9861L37.119 75.079C37.1037 75.1051 37.0988 75.1284 37.1043 75.149C37.1303 75.1643 37.1613 75.1561 37.1971 75.1247C37.233 75.0932 37.259 75.1084 37.2753 75.1703C37.2492 75.1551 37.2286 75.1605 37.2133 75.1866C37.1981 75.2126 37.1905 75.2257 37.1905 75.2257L37.2068 75.2876L37.2458 75.3104C37.2915 75.2322 37.3013 75.1856 37.2753 75.1703C37.347 75.1074 37.3617 75.0374 37.3194 74.9603C37.3194 74.9603 37.3064 74.9527 37.2803 74.9374C37.2695 74.8962 37.2847 74.8701 37.326 74.8593C37.3098 74.7974 37.3223 74.761 37.3636 74.7502C37.3842 74.7448 37.3891 74.7214 37.3783 74.6802C37.3262 74.6497 37.3311 74.6264 37.393 74.6101L37.3849 74.5792C37.3588 74.564 37.3458 74.5564 37.3458 74.5564C37.361 74.5303 37.3659 74.507 37.3605 74.4863L37.395 74.1134L37.4392 73.9033C37.4544 73.8773 37.4767 73.7942 37.5061 73.6542L37.5209 73.5841L37.6218 73.5907L37.6528 73.5826C37.668 73.5566 37.6626 73.5359 37.6365 73.5207L37.6056 73.5288L37.5209 73.5841L37.5422 73.4131L37.596 73.3659L37.6269 73.3578C37.6584 73.3937 37.6893 73.3856 37.7198 73.3335L37.772 73.1543C37.7612 73.1131 37.7661 73.0897 37.7867 73.0843L37.8015 73.0143L37.8177 73.0762L37.7832 73.4492L37.7685 73.5192C37.738 73.5713 37.7358 73.6049 37.7619 73.6202C37.7467 73.6462 37.7445 73.6799 37.7553 73.7211C37.7813 73.7364 37.7867 73.757 37.7715 73.783L37.7796 73.814C37.7796 73.814 37.7693 73.8167 37.7487 73.8221C37.7487 73.8221 37.746 73.8118 37.7406 73.7912L37.7325 73.7602L37.7243 73.7293L37.7325 73.7602L37.703 73.9003C37.6726 73.9524 37.691 73.9806 37.7583 73.985L37.7746 74.0469C37.7549 74.1403 37.7533 74.2179 37.7695 74.2798C37.7695 74.2798 37.7646 74.3032 37.7548 74.3498C37.7602 74.3705 37.7835 74.3754 37.8248 74.3646L37.8492 74.4574C37.8285 74.4628 37.8209 74.4758 37.8263 74.4965L37.8882 74.4802L37.9405 74.3011C37.9808 74.2023 38.0151 74.039 38.0435 73.811L38.0714 73.539C38.066 73.5183 38.0633 73.508 38.0633 73.508C38.0839 73.5026 38.0942 73.4999 38.0942 73.4999L38.1024 73.5309C38.0577 73.697 38.044 73.8549 38.0613 74.0048L38.0694 74.0357C38.09 74.0303 38.0976 74.0173 38.0922 73.9967L38.1348 73.6547C38.1447 73.608 38.1719 73.5016 38.2165 73.3355C38.2111 73.3149 38.2084 73.3045 38.2084 73.3045C38.2236 73.2785 38.2182 73.2579 38.1922 73.2426C38.1868 73.222 38.1944 73.209 38.215 73.2036C38.2302 73.1775 38.2324 73.1439 38.2216 73.1026L38.2607 73.1254C38.2455 73.1515 38.2406 73.1748 38.246 73.1954C38.272 73.2107 38.2774 73.2313 38.2622 73.2574C38.247 73.2834 38.2556 73.3583 38.2881 73.4821L38.3419 73.435L38.3779 73.1939C38.4083 73.1418 38.4442 73.1104 38.4855 73.0995L38.5393 73.0524L38.554 72.9823L38.5311 73.0214L38.4774 73.0686C38.4665 73.0273 38.4714 73.004 38.4921 72.9986C38.4867 72.9779 38.4992 72.9416 38.5296 72.8895L38.5606 72.8814L38.5819 72.7103C38.6025 72.7049 38.6128 72.7022 38.6128 72.7022C38.6074 72.6816 38.6047 72.6713 38.6047 72.6713C38.6873 72.6496 38.7123 72.5769 38.6798 72.4531C38.6744 72.4324 38.682 72.4194 38.7027 72.414C38.7385 72.3826 38.7695 72.3744 38.7955 72.3897C38.8889 72.4093 38.9535 72.4034 38.9894 72.3719L39.0513 72.3557C39.0567 72.3763 39.0491 72.3893 39.0284 72.3947L38.8539 72.7383L38.7884 73.1193C38.7678 73.1247 38.7602 73.1378 38.7656 73.1584C38.7862 73.153 38.7938 73.14 38.7884 73.1193C38.8243 73.0879 38.852 73.0255 38.8716 72.9321L38.9239 72.753C38.9229 72.665 38.9762 72.5739 39.0837 72.4795C39.1196 72.448 39.1473 72.3856 39.167 72.2922L39.2355 72.175L39.2974 72.1588L39.3217 72.2516L39.2989 72.2907L39.3298 72.2826C39.3711 72.2718 39.3863 72.2457 39.3755 72.2044C39.3495 72.1892 39.3467 72.1789 39.3674 72.1735C39.3826 72.1474 39.4005 72.1317 39.4212 72.1263C39.4831 72.1101 39.5211 72.0449 39.5353 71.9309C39.5353 71.9309 39.5962 71.8268 39.718 71.6184L39.7261 71.6493L39.6592 71.8985C39.6548 71.9658 39.671 72.0277 39.7079 72.0842C39.76 72.1146 39.7963 72.1272 39.817 72.1217C39.8789 72.1055 39.8946 72.1234 39.8642 72.1755L39.8266 72.2846C39.7048 72.493 39.6248 72.7345 39.5866 73.0092C39.5135 73.4033 39.4817 73.7866 39.4912 74.1591C39.477 74.2731 39.4655 74.3974 39.4567 74.532C39.4685 74.6612 39.4673 74.7828 39.4531 74.8968C39.4409 75.1868 39.4059 75.5157 39.3481 75.8838C39.3447 76.0391 39.319 76.2774 39.271 76.5988C39.2666 76.6661 39.2551 76.7904 39.2364 76.9717C39.2331 77.127 39.2063 77.2773 39.1563 77.4228L39.1659 77.5857L39.0903 78.4326L39.0588 79.0694C39.0369 79.406 39.016 79.621 38.9964 79.7143C39.0083 79.8436 38.9919 79.9912 38.9472 80.1573C38.9242 80.406 38.8729 80.673 38.7934 80.9585C38.8063 81.1757 38.8029 81.331 38.7833 81.4244L38.7686 81.4944L38.726 81.8364L38.7041 82.6361L38.6727 83.2729C38.6683 83.3402 38.6612 83.3972 38.6514 83.4439C38.6361 83.47 38.6209 83.496 38.6057 83.5221C38.6165 83.5633 38.6143 83.597 38.5991 83.623C38.6045 83.6437 38.5974 83.7007 38.5778 83.794C38.5199 84.1621 38.466 84.4189 38.4159 84.5643L38.3718 84.7744C38.3826 84.8157 38.3777 84.839 38.357 84.8444L38.218 85.5756C38.1277 85.8199 38.102 86.0582 38.1409 86.2906L38.0901 86.6016L38.0424 87.1765C38.0076 87.296 37.9858 87.423 37.977 87.5576C37.9834 87.6662 37.9768 87.7672 37.9572 87.8605C37.9321 87.9333 37.9413 88.0522 37.9846 88.2173C38.0062 88.2998 38.061 88.3406 38.149 88.3396C38.2163 88.344 38.2554 88.3668 38.2662 88.4081C38.2977 88.4439 38.3085 88.4852 38.2987 88.5319L38.2789 88.8348L38.3129 89.0905C38.3345 89.1731 38.3171 89.2328 38.2606 89.2697L38.0455 89.4584L37.9917 89.5056C37.9721 89.599 37.9134 89.6695 37.8156 89.7172C37.7385 89.7595 37.6896 89.7833 37.669 89.7888L37.4766 89.9385C37.4354 89.9493 37.3762 89.9758 37.299 90.0181C37.2273 90.081 37.1578 90.1103 37.0905 90.1059L36.5481 90.182L36.338 90.1379C35.9753 90.1007 35.711 90.0597 35.5449 90.0151C35.4776 90.0107 35.4178 89.9932 35.3658 89.9628C35.3343 89.9269 35.2952 89.9041 35.2485 89.8943C35.0608 89.7671 34.8568 89.578 34.6366 89.327C34.4532 89.1325 34.2455 88.8451 34.0135 88.4649L33.5791 87.8179L33.3482 87.3161C33.2745 87.2031 33.2241 87.095 33.197 86.9918C33.1125 86.8376 33.0008 86.5801 32.8621 86.2195C32.809 86.1011 32.7424 85.9311 32.6622 85.7095C32.582 85.488 32.5176 85.2843 32.4689 85.0986C32.4212 85.0008 32.3865 84.9107 32.3649 84.8281C32.3584 84.7196 32.3314 84.6164 32.2837 84.5186L32.1619 84.0543C32.0665 83.8588 32.0053 83.7094 31.9782 83.6063L31.7052 82.8177C31.6619 82.6526 31.5817 82.4311 31.4647 82.153C31.4268 82.0086 31.3493 81.7973 31.2323 81.5192C31.2161 81.4573 31.1819 81.4111 31.1298 81.3807L31.1004 81.5207C31.0611 81.7075 31.042 81.8448 31.043 81.9328C31.0647 82.0153 31.0684 82.1136 31.0542 82.2276C31.0346 82.321 31.0199 82.391 31.01 82.4377L30.9527 82.8497C30.9233 82.9897 30.8938 83.1298 30.8644 83.2698C30.835 83.4099 30.8132 83.5369 30.7989 83.6509C30.7465 84.0396 30.7078 84.2703 30.6827 84.343C30.6783 84.4104 30.6511 84.5168 30.601 84.6622C30.6173 84.7241 30.6178 84.7681 30.6026 84.7941C30.6134 84.8354 30.5916 84.9624 30.5371 85.1752C30.5479 85.2165 30.5261 85.3435 30.4717 85.5563L30.3113 86.4585L30.1494 87.2288L30.0429 88.0838L29.987 88.6277C29.9532 88.8351 29.9314 88.9621 29.9216 89.0088L29.8937 89.2808C29.8686 89.3535 29.8517 89.4572 29.8429 89.5918C29.8439 89.6798 29.8477 89.7781 29.8541 89.8867C29.8551 89.9746 29.8458 90.0653 29.8262 90.1586C29.815 90.5365 29.8473 90.8699 29.9231 91.1588L30.0449 91.6231L30.1504 92.0255C30.2198 92.2058 30.3749 92.4187 30.6157 92.6643C30.6211 92.6849 30.6342 92.6926 30.6548 92.6871C30.6808 92.7024 30.6966 92.7203 30.702 92.7409C30.728 92.7562 30.7465 92.7844 30.7573 92.8257C30.716 92.8365 30.6927 92.8316 30.6873 92.811C30.6612 92.7957 30.633 92.8142 30.6025 92.8663C30.5775 92.939 30.5259 92.9525 30.4478 92.9069L30.2605 92.8236ZM28.6911 92.0112C28.6704 92.0167 28.6574 92.009 28.652 91.9884L28.5789 91.7098L28.6261 91.7636L28.6829 91.9803C28.709 91.9955 28.722 92.0031 28.722 92.0031C28.7014 92.0085 28.6911 92.0112 28.6911 92.0112ZM28.8149 91.9788C28.7942 91.9842 28.7812 91.9766 28.7758 91.9559L28.6895 91.8793L28.6961 91.7783L28.7271 91.7702C28.7586 91.8061 28.7851 91.8653 28.8068 91.9478L28.8149 91.9788ZM28.6718 91.6855C28.6403 91.6496 28.6094 91.6577 28.5789 91.7098L28.5774 91.5779C28.572 91.5573 28.5796 91.5442 28.6002 91.5388C28.6057 91.5595 28.6084 91.5698 28.6084 91.5698L28.7027 91.6774C28.7082 91.698 28.7005 91.711 28.6799 91.7164L28.6718 91.6855ZM28.1283 91.001L28.1334 90.7681L28.1253 90.7371L28.1334 90.7681C28.1605 90.8712 28.1691 90.9462 28.1593 90.9928L28.1283 91.001ZM28.7682 91.2963C28.7888 91.2909 28.7964 91.2778 28.791 91.2572C28.8063 91.2312 28.8058 91.1872 28.7895 91.1253L28.7814 91.0943C28.7608 91.0997 28.7531 91.1128 28.7586 91.1334C28.7433 91.1594 28.7438 91.2034 28.7601 91.2653L28.7682 91.2963ZM28.5241 88.9784L28.446 88.9327L28.4247 89.1037L28.4556 89.0956L28.5241 88.9784ZM27.4631 87.8341C27.4925 87.6941 27.5149 87.611 27.5301 87.585L27.522 87.554L27.5301 87.585L27.5022 87.857C27.4816 87.8624 27.4739 87.8754 27.4794 87.896L27.4631 87.8341ZM28.3978 88.1183C28.4533 87.9935 28.4567 87.8382 28.4079 87.6525L28.377 87.6606C28.3672 87.7073 28.3574 87.7539 28.3476 87.8006C28.3323 87.8267 28.3328 87.8707 28.3491 87.9326C28.3707 88.0151 28.3767 88.0797 28.3668 88.1264L28.375 88.1573L28.3978 88.1183ZM29.2279 86.7427C29.2486 86.7372 29.2562 86.7242 29.2508 86.7036L29.2802 86.5635L29.2721 86.5326L29.2411 86.5407C29.2466 86.5613 29.2394 86.6183 29.2198 86.7117L29.2279 86.7427ZM29.6172 84.821L29.5862 84.8292L29.5339 85.0083L29.5421 85.0392L29.573 85.0311L29.6172 84.821ZM28.6875 84.304C28.7072 84.2106 28.7143 84.1536 28.7089 84.133L28.7007 84.102L28.6566 84.3121L28.6875 84.304ZM29.6385 84.65C29.6591 84.6446 29.6667 84.6316 29.6613 84.611L29.6841 84.5719C29.7322 84.2505 29.7785 84.0068 29.8232 83.8407C29.8178 83.8201 29.8172 83.7761 29.8216 83.7088C29.826 83.6414 29.8359 83.5948 29.8511 83.5687L29.9069 83.0247L29.9805 82.6746L29.9724 82.6437C29.9517 82.6491 29.9441 82.6621 29.9495 82.6827L29.8825 82.9319L29.9069 83.0247C29.9069 83.0247 29.8917 83.0508 29.8612 83.1029C29.774 83.611 29.7188 83.9894 29.6958 84.238L29.6303 84.6191L29.6385 84.65ZM33.7324 85.6273L33.6771 85.5426L33.6623 85.6126L33.7177 85.6974L33.7324 85.6273ZM33.6111 84.5344L33.5248 84.4577C33.5194 84.4371 33.5064 84.4295 33.4858 84.4349L33.4939 84.4659L33.5573 84.5815C33.5779 84.5761 33.591 84.5837 33.5964 84.6044L33.6111 84.5344ZM30.0378 82.2626L30.051 82.0606L30.0429 82.0297L29.9987 82.2398L30.0069 82.2707L30.0378 82.2626ZM33.4223 84.3192L33.4371 84.2492L33.4289 84.2182C33.4289 84.2182 33.4186 84.2209 33.398 84.2263C33.398 84.2263 33.4007 84.2367 33.4061 84.2573L33.3833 84.2964C33.4354 84.3268 33.4614 84.342 33.4614 84.342L33.4223 84.3192ZM33.5649 83.2232L33.5406 83.1303L33.5096 83.1384L33.4787 83.1465L33.4802 83.2785L33.5111 83.2704L33.5649 83.2232ZM32.8601 82.6802L32.8276 82.5564L32.7886 82.5336L32.7967 82.5645C32.7815 82.5906 32.7793 82.6242 32.7901 82.6655L32.7982 82.6965L32.8292 82.6883L32.8601 82.6802ZM32.1264 81.6486L32.102 81.5558L32.0939 81.5248L32.063 81.5329C32.0792 81.5948 32.0797 81.6388 32.0645 81.6649C32.0699 81.6855 32.0932 81.6904 32.1345 81.6796L32.1264 81.6486ZM32.7668 81.3152L32.7896 81.2762L32.7815 81.2452L32.7196 81.2615C32.7196 81.2615 32.7092 81.2642 32.6886 81.2696C32.6886 81.2696 32.6913 81.2799 32.6967 81.3005C32.7228 81.3158 32.7412 81.344 32.752 81.3853L32.7668 81.3152ZM32.5912 80.8981C32.5858 80.8775 32.5831 80.8672 32.5831 80.8672C32.6037 80.8618 32.614 80.8591 32.614 80.8591L32.6287 80.789C32.6081 80.7945 32.5924 80.7765 32.5815 80.7353L32.5506 80.7434L32.5978 80.7972C32.6032 80.8178 32.5956 80.8308 32.575 80.8362L32.5912 80.8981ZM37.0941 81.6689L37.0256 81.7862L37.0646 81.809L37.0941 81.6689ZM30.8284 77.4568C30.823 77.4361 30.8203 77.4258 30.8203 77.4258C30.8409 77.4204 30.8512 77.4177 30.8512 77.4177L30.7959 77.333L30.7812 77.403L30.8284 77.4568ZM36.9104 81.2209C36.9148 81.1536 36.9452 81.1015 37.0017 81.0646L36.9627 81.0418L36.9317 81.0499L36.8632 81.1671C36.8632 81.1671 36.8659 81.1774 36.8713 81.198C36.8713 81.198 36.861 81.2008 36.8404 81.2062L36.9104 81.2209ZM37.088 81.1412C37.1705 81.1196 37.1907 81.0702 37.1484 80.993L37.1403 80.9621L37.0931 80.9083L37.0783 80.9783C37.1044 80.9936 37.1022 81.0272 37.0718 81.0793L37.057 81.1493L37.088 81.1412ZM37.0266 80.5288L36.9875 80.5059L36.919 80.6231L36.9972 80.6688L37.0266 80.5288ZM36.9977 80.0401C37.0183 80.0347 37.0259 80.0217 37.0205 80.001C37.103 79.9794 37.1362 79.9376 37.12 79.8757C37.1146 79.8551 37.1015 79.8474 37.0809 79.8529L37.0581 79.8919C37.0689 79.9332 37.051 79.9489 37.0043 79.9391L36.9896 80.0091L36.9977 80.0401ZM37.3549 79.384L37.3696 79.314L37.3534 79.2521L37.2834 79.2374L37.2915 79.2683C37.3175 79.2835 37.3229 79.3042 37.3077 79.3302L37.293 79.4002L37.3549 79.384ZM37.1956 79.0288L37.2235 78.7568L37.1616 78.7731L37.1697 78.804C37.1903 78.7986 37.2061 78.8165 37.2169 78.8578C37.1864 78.9099 37.1739 78.9463 37.1793 78.9669L37.2037 79.0598L37.1956 79.0288ZM37.3732 78.9491C37.3938 78.9437 37.4014 78.9307 37.396 78.9101L37.4254 78.77L37.4173 78.7391L37.3864 78.7472L37.326 78.8954L37.3732 78.9491ZM37.3701 78.6853C37.3908 78.6799 37.4163 78.6511 37.4468 78.599C37.4468 78.599 37.4364 78.6017 37.4158 78.6071C37.4104 78.5865 37.4104 78.5865 37.4158 78.6071C37.3745 78.618 37.3593 78.644 37.3701 78.6853ZM37.4924 78.5209L37.4762 78.459L37.4224 78.5062L37.3914 78.5143C37.3969 78.5349 37.3892 78.5479 37.3686 78.5533L37.4386 78.5681L37.4924 78.5209ZM37.4275 78.2732L37.4356 78.3042C37.4769 78.2934 37.4948 78.2776 37.4894 78.257C37.484 78.2364 37.4552 78.2108 37.4031 78.1804L37.3737 78.3204L37.4275 78.2732ZM37.4731 78.1951C37.4677 78.1745 37.465 78.1642 37.465 78.1642C37.4857 78.1587 37.496 78.156 37.496 78.156L37.4879 78.1251C37.4879 78.1251 37.4824 78.1044 37.4716 78.0632L37.4097 78.0794L37.4569 78.1332L37.4731 78.1951ZM37.3316 78.0337L37.33 77.9018L37.3219 77.8709L37.291 77.879L37.2925 78.0109L37.3006 78.0419L37.3316 78.0337ZM37.5173 77.985C37.5119 77.9644 37.5065 77.9438 37.501 77.9231C37.5109 77.8764 37.531 77.8271 37.5614 77.775L37.4752 77.6983L37.4442 77.7065L37.4686 77.7993L37.4767 77.8303C37.4615 77.8563 37.4593 77.89 37.4701 77.9312C37.4755 77.9519 37.4706 77.9752 37.4554 78.0013L37.4635 78.0322L37.5173 77.985ZM37.5518 77.6121C37.5257 77.5969 37.5203 77.5762 37.5356 77.5502C37.5714 77.5187 37.5866 77.4927 37.5812 77.472L37.565 77.4101L37.5112 77.4573L37.5046 77.5583L37.4589 77.6364L37.5518 77.6121ZM37.6157 77.0991C37.6103 77.0784 37.6179 77.0654 37.6386 77.06L37.5767 77.0762C37.5767 77.0762 37.5663 77.0789 37.5457 77.0844C37.5457 77.0844 37.5484 77.0947 37.5538 77.1153L37.601 77.1691L37.6157 77.0991ZM37.6112 76.7033C37.6416 76.6512 37.6514 76.6045 37.6406 76.5632L37.5721 76.6804C37.5775 76.7011 37.5905 76.7087 37.6112 76.7033ZM37.7269 76.6398C37.7681 76.629 37.7861 76.6133 37.7806 76.5927C37.7752 76.572 37.7622 76.5644 37.7416 76.5698L37.6878 76.617C37.6932 76.6376 37.6959 76.648 37.6959 76.648C37.7165 76.6426 37.7269 76.6398 37.7269 76.6398ZM37.8365 76.0487C37.8256 76.0074 37.8278 75.9738 37.8431 75.9477L37.8121 75.9558L37.8055 76.0568L37.8136 76.0878L37.8365 76.0487ZM37.8405 75.0552C37.8405 75.0552 37.8558 75.0291 37.8862 74.977L37.9207 74.6041L37.9045 74.5422L37.8963 74.5112C37.8811 74.5372 37.8529 74.5557 37.8116 74.5665L37.7888 74.6056C37.8409 74.636 37.8669 74.6512 37.8669 74.6512C37.8723 74.6719 37.8647 74.6849 37.8441 74.6903C37.8234 74.6957 37.8158 74.7088 37.8212 74.7294C37.8483 74.8326 37.8466 74.9102 37.8162 74.9623L37.8405 75.0552ZM37.5579 74.1037C37.6036 74.0256 37.6264 73.9865 37.6264 73.9865L37.5564 73.9718C37.5618 73.9924 37.5493 74.0288 37.5188 74.0809L37.5579 74.1037ZM37.6168 73.8236C37.6113 73.803 37.5983 73.7954 37.5777 73.8008L37.563 73.8708L37.6102 73.9246L37.6168 73.8236ZM37.669 73.6445L37.599 73.6298L37.5762 73.6689C37.5762 73.6689 37.5789 73.6792 37.5843 73.6998C37.5843 73.6998 37.5946 73.6971 37.6152 73.6917L37.669 73.6445ZM38.3195 72.8453L38.3881 72.7281L38.3896 72.86L38.3667 72.8991L38.3195 72.8453ZM38.9432 73.0787C38.9378 73.0581 38.9503 73.0217 38.9807 72.9696L38.9416 72.9468C38.9004 72.9576 38.8852 72.9837 38.896 73.025L38.9432 73.0787ZM38.3881 72.7281C38.3718 72.6662 38.3458 72.651 38.3099 72.6824C38.3045 72.6618 38.317 72.6254 38.3475 72.5733L38.3784 72.5652C38.373 72.5446 38.3909 72.5289 38.4322 72.518C38.443 72.5593 38.4408 72.593 38.4256 72.619C38.431 72.6396 38.4185 72.676 38.3881 72.7281ZM38.3738 72.1694L38.4033 72.0294L38.4423 72.0522L38.382 72.2004L38.3738 72.1694ZM51.8433 87.9236C51.8368 87.815 51.7897 87.7612 51.7017 87.7622C51.6757 87.747 51.6729 87.7367 51.6936 87.7313C51.724 87.6792 51.7338 87.6325 51.723 87.5912C51.6916 87.5554 51.722 87.5033 51.8143 87.4349C51.835 87.4295 51.8426 87.4165 51.8372 87.3959L51.8062 87.404L51.7672 87.3812L51.7981 87.373C51.8394 87.3622 51.8519 87.3258 51.8357 87.2639L51.8894 87.2167L52.1812 86.9417C52.2117 86.8896 52.2372 86.8609 52.2578 86.8555L52.1259 86.857C51.9196 86.9111 51.7518 86.9441 51.6225 86.9559L51.5525 86.9412L51.5672 86.8712C51.6031 86.8397 51.5977 86.8191 51.551 86.8093L51.5429 86.7783C51.5635 86.7729 51.5711 86.7599 51.5657 86.7393C51.6276 86.723 51.7151 86.678 51.8281 86.6043C51.8487 86.5989 51.8563 86.5858 51.8509 86.5652L51.789 86.5814C51.6445 86.6193 51.5337 86.6594 51.4566 86.7017L51.3947 86.7179L51.3409 86.7651L51.3556 86.6951L51.3475 86.6642L51.3166 86.6723L51.1618 86.7129L51.1308 86.721C51.12 86.6797 51.1249 86.6564 51.1456 86.651C51.1402 86.6303 51.1374 86.62 51.1374 86.62C51.1581 86.6146 51.1684 86.6119 51.1684 86.6119C51.3074 86.5534 51.5106 86.445 51.7778 86.2866L51.8935 86.2232L51.9163 86.1841L51.8773 86.1613L51.7306 86.2328C51.7306 86.2328 51.7203 86.2356 51.6997 86.241C51.6997 86.241 51.697 86.2306 51.6916 86.21L51.7144 86.1709L52.2538 85.831L52.3532 85.7056L52.4608 85.6113C52.5325 85.5483 52.5939 85.4881 52.645 85.4306C52.7221 85.3883 52.7966 85.3357 52.8683 85.2728C52.8889 85.2674 52.8965 85.2544 52.8911 85.2337L52.8292 85.25C52.7162 85.3237 52.6391 85.366 52.5978 85.3768L52.5359 85.3931L52.4121 85.4255C52.2318 85.4949 52.0183 85.606 51.7717 85.7589C51.5762 85.8543 51.4426 85.9335 51.3709 85.9964L51.278 86.0207L51.1232 86.0613L51.0923 86.0695L51.1151 86.0304L51.4541 85.8091C51.4541 85.8091 51.4693 85.7831 51.4998 85.731L51.4069 85.7554C51.2939 85.8291 51.2038 85.8638 51.1364 85.8594C51.0539 85.881 50.9637 85.9157 50.866 85.9634C50.7736 86.0317 50.7068 86.0713 50.6655 86.0821L50.6036 86.0984L50.5027 86.0918L50.5646 86.0755L50.8041 85.9796L51.2668 85.7259L51.6368 85.4966C51.678 85.4857 51.7063 85.4673 51.7215 85.4413C51.7574 85.4098 51.7829 85.3811 51.7981 85.355C51.8394 85.3442 51.8959 85.3073 51.9676 85.2444C52.0089 85.2336 52.0447 85.2021 52.0752 85.15C52.0383 85.0935 51.997 85.1043 51.9514 85.1825L51.9204 85.1906C51.915 85.17 51.9226 85.1569 51.9432 85.1515C51.9585 85.1255 51.997 85.1043 52.0589 85.0881L52.1746 85.0247C52.1953 85.0193 52.2056 85.0166 52.2056 85.0166C52.2002 84.9959 52.1975 84.9856 52.1975 84.9856L52.1584 84.9628C52.1378 84.9682 52.1301 84.9812 52.1356 85.0018L52.0346 84.9952L52.0884 84.948L52.4811 84.6796C52.5941 84.6059 52.7147 84.5191 52.8429 84.4193L52.8657 84.3802L52.8038 84.3965C52.7169 84.4854 52.6474 84.5147 52.5953 84.4843C52.5747 84.4897 52.5589 84.4717 52.5481 84.4305C52.5319 84.3686 52.5417 84.3219 52.5775 84.2904C52.634 84.2536 52.6726 84.2324 52.6932 84.227L53.0926 83.8576L53.3224 83.5988C53.4506 83.499 53.5734 83.3786 53.6908 83.2375L54.0821 82.8372C54.3723 82.4302 54.5098 82.2398 54.4946 82.2658C54.6685 82.0879 54.7859 81.9468 54.8467 81.8426L55.1289 81.4047L55.4567 80.8887L55.6541 80.5061C55.6585 80.4387 55.6911 80.353 55.752 80.2488C55.8772 79.8851 55.9447 79.68 55.9545 79.6333C56.0089 79.4205 55.9993 79.2576 55.9255 79.1446L55.9093 79.0827L55.8931 79.0208L55.8784 79.0909L55.8099 79.2081L55.7789 79.2162L55.7708 79.1852C55.786 79.1592 55.7882 79.1255 55.7774 79.0843L55.7302 79.0305L55.7139 78.9686C55.6977 78.9067 55.669 78.8811 55.6277 78.8919C55.5397 78.893 55.4235 78.9124 55.2791 78.9503L55.1472 78.9518C55.1005 78.942 55.0359 78.9479 54.9533 78.9696C54.8914 78.9858 54.8371 78.989 54.7904 78.9792C54.7383 78.9488 54.7096 78.9232 54.7042 78.9026C54.6933 78.8613 54.7086 78.8353 54.7498 78.8244C54.7651 78.7984 54.7624 78.7881 54.7417 78.7935C54.7363 78.7729 54.7233 78.7652 54.7027 78.7707C54.6766 78.7554 54.6272 78.7353 54.5545 78.7103C54.4763 78.6646 54.3987 78.6629 54.3216 78.7052C54.3009 78.7106 54.2906 78.7133 54.2906 78.7133C54.2852 78.6927 54.2825 78.6824 54.2825 78.6824C54.225 78.6313 54.181 78.6318 54.1506 78.6839C54.1353 78.7099 54.1174 78.7257 54.0968 78.7311L54.012 78.7864L53.9811 78.7945C53.9713 78.8412 53.9561 78.8672 53.9354 78.8727C53.9094 78.8574 53.8964 78.8498 53.8964 78.8498C53.7976 78.8096 53.715 78.8312 53.6487 78.9148L53.5493 79.0401C53.5188 79.0922 53.4906 79.1106 53.4645 79.0954C53.4645 79.0954 53.4255 79.0726 53.3473 79.0269L53.292 78.9422L53.2448 78.8884C53.2079 78.8319 53.1531 78.7911 53.0804 78.7661C53.0023 78.7204 52.9399 78.6927 52.8932 78.6829C52.8204 78.6578 52.7814 78.635 52.776 78.6144C52.7553 78.6198 52.745 78.6225 52.745 78.6225C52.7602 78.5964 52.7678 78.5834 52.7678 78.5834L52.7516 78.5215C52.7516 78.5215 52.7543 78.5318 52.7597 78.5525C52.7597 78.5525 52.7494 78.5552 52.7288 78.5606L52.6897 78.5377C52.6843 78.5171 52.6713 78.5095 52.6506 78.5149L52.3705 78.456C52.3238 78.4462 52.2772 78.4364 52.2305 78.4266C52.1838 78.4168 52.1344 78.3967 52.0823 78.3662C51.9477 78.3574 51.8722 78.3221 51.856 78.2602C51.8506 78.2395 51.8376 78.2319 51.8169 78.2373L51.5906 78.1313L51.5206 78.1166C51.4945 78.1014 51.4734 78.0628 51.4572 78.0009L51.55 77.9765C51.5913 77.9657 51.6092 77.95 51.6038 77.9293C51.6136 77.8827 51.6055 77.8517 51.5795 77.8365C51.548 77.8006 51.5399 77.7697 51.5551 77.7436C51.5703 77.7176 51.5649 77.6969 51.5389 77.6817C51.5334 77.6611 51.5204 77.6535 51.4998 77.6589C51.4477 77.6284 51.4189 77.6029 51.4135 77.5823C51.4027 77.541 51.4179 77.5149 51.4592 77.5041L51.5683 77.5417L51.5992 77.5335C51.5938 77.5129 51.5808 77.5053 51.5602 77.5107C51.5341 77.4955 51.5005 77.4933 51.4592 77.5041L51.3729 77.4275L51.3257 77.3737C51.3464 77.3683 51.3567 77.3656 51.3567 77.3656C51.3719 77.3395 51.3926 77.3341 51.4186 77.3493C51.5586 77.3788 51.6417 77.4011 51.6677 77.4163C51.7144 77.4261 51.7481 77.4283 51.7687 77.4229C51.7894 77.4175 51.8046 77.3915 51.8144 77.3448L51.8453 77.3367C51.8453 77.3367 51.8481 77.347 51.8535 77.3676C51.8535 77.3676 51.8638 77.3649 51.8844 77.3595C51.8952 77.4008 51.911 77.4187 51.9316 77.4133L52.0245 77.3889L52.1402 77.3255C52.1608 77.3201 52.1814 77.3147 52.2021 77.3093C52.2433 77.2984 52.2694 77.3137 52.2802 77.3549L52.3112 77.3468L52.2249 77.2702C52.1934 77.2343 52.1777 77.2164 52.1777 77.2164C52.1983 77.211 52.1956 77.2007 52.1696 77.1855C52.1642 77.1648 52.1615 77.1545 52.1615 77.1545L52.0214 77.1251C52.0008 77.1305 51.9802 77.1359 51.9595 77.1413C51.9335 77.1261 51.915 77.0978 51.9042 77.0566L51.8733 77.0647L51.8504 77.1038C51.8765 77.119 51.8689 77.132 51.8276 77.1428L51.6728 77.1834C51.5957 77.2257 51.505 77.2164 51.4008 77.1555C51.3487 77.1251 51.3151 77.1229 51.2999 77.1489L51.2298 77.1342C51.219 77.0929 51.2239 77.0696 51.2446 77.0642C51.2391 77.0435 51.2571 77.0278 51.2983 77.017C51.319 77.0116 51.3293 77.0089 51.3293 77.0089C51.3239 76.9882 51.3212 76.9779 51.3212 76.9779L51.2902 76.986L51.2283 77.0023C51.2283 77.0023 51.2207 77.0153 51.2055 77.0413C51.1848 77.0468 51.1718 77.0391 51.1664 77.0185C51.1458 77.0239 51.13 77.006 51.1192 76.9647L51.103 76.9028C51.0563 76.893 51.033 76.8881 51.033 76.8881C51.0536 76.8827 51.0742 76.8773 51.0949 76.8719C51.1155 76.8664 51.1334 76.8507 51.1487 76.8247C51.1845 76.7932 51.1867 76.7596 51.1552 76.7237L51.1243 76.7318C51.1145 76.7785 51.1015 76.7709 51.0852 76.709L51.0233 76.7252C50.9929 76.7773 50.9592 76.7751 50.9223 76.7186C50.9169 76.698 50.8882 76.6724 50.8361 76.642C50.8307 76.6214 50.8176 76.6137 50.797 76.6192C50.7916 76.5985 50.7992 76.5855 50.8198 76.5801C50.8405 76.5747 50.8508 76.572 50.8508 76.572C50.8454 76.5513 50.8427 76.541 50.8427 76.541L50.7321 76.3715L50.7468 76.3015L50.7615 76.2315L50.7305 76.2396L50.6996 76.2477C50.6735 76.2325 50.6551 76.2043 50.6443 76.163C50.628 76.1011 50.6275 76.0571 50.6428 76.0311C50.658 76.005 50.6629 75.9817 50.6575 75.961C50.6521 75.9404 50.6466 75.9198 50.6412 75.8991L50.5874 75.9463L50.5646 75.9854L50.5255 75.9626L50.5468 75.7915L50.5616 75.7215C50.5355 75.7063 50.5301 75.6857 50.5453 75.6596C50.5551 75.6129 50.5573 75.5793 50.5519 75.5586C50.5726 75.5532 50.5883 75.5712 50.5991 75.6124L50.5925 75.7134L50.6235 75.7053C50.6691 75.6271 50.6915 75.5441 50.6905 75.4561C50.7297 75.2694 50.7825 75.1343 50.8488 75.0507C50.9097 74.9465 50.9401 74.8944 50.9401 74.8944C50.9032 74.8379 50.9027 74.794 50.9386 74.7625C50.9897 74.705 51.0228 74.6632 51.038 74.6372C51.0577 74.5438 51.1534 74.3202 51.3252 73.9663C51.3405 73.9403 51.322 73.912 51.2699 73.8816C51.2645 73.861 51.2466 73.8767 51.2162 73.9288C51.2162 73.9288 51.2189 73.9391 51.2243 73.9597C51.2243 73.9597 51.214 73.9625 51.1933 73.9679C51.1108 73.9895 51.0521 74.06 51.0172 74.1795L51.0025 74.2495L50.8198 74.5621C50.8253 74.5827 50.8177 74.5957 50.797 74.6011C50.7764 74.6065 50.7585 74.6223 50.7432 74.6483C50.702 74.6591 50.684 74.6749 50.6894 74.6955C50.6394 74.841 50.5888 74.9425 50.5377 75C50.5431 75.0206 50.5355 75.0336 50.5149 75.039L50.5068 75.0081C50.4949 74.8789 50.5543 74.6427 50.6849 74.2997L50.6768 74.2688L50.6458 74.2769C50.5839 74.2931 50.5328 74.3506 50.4926 74.4494C50.4675 74.5221 50.4344 74.5639 50.3931 74.5747C50.3931 74.5747 50.3958 74.5851 50.4012 74.6057C50.4012 74.6057 50.3909 74.6084 50.3703 74.6138L50.385 74.5438C50.4002 74.5177 50.4154 74.4917 50.4307 74.4656C50.4611 74.4136 50.4785 74.3538 50.4829 74.2865C50.4927 74.2398 50.5357 74.1514 50.6118 74.0211C50.6368 73.9484 50.6749 73.8833 50.726 73.8258C50.7152 73.7845 50.6994 73.7666 50.6788 73.772C50.668 73.7307 50.6702 73.6971 50.6854 73.671L51.0132 73.155L51.2725 72.7561L51.4486 72.5445L51.6541 72.1929C51.765 71.9432 51.864 71.7739 51.9509 71.685C51.9715 71.6795 51.9819 71.6768 51.9819 71.6768C51.9765 71.6562 51.9737 71.6459 51.9737 71.6459L52.1042 71.5124C52.165 71.4082 52.2134 71.3404 52.2493 71.309L52.5624 70.8629L52.6928 70.7295C52.8656 70.4636 53.0569 70.2259 53.2667 70.0166L53.526 69.6177L53.9776 69.0692L54.3835 68.5988C54.4552 68.5359 54.5368 68.4263 54.6281 68.27L54.8123 68.0894L55.3715 67.4465L55.7627 67.0461L56.0007 66.8183C56.1029 66.7032 56.1822 66.6273 56.2387 66.5904C56.2691 66.5383 56.3202 66.4808 56.3919 66.4179L56.5452 66.2454C56.6473 66.1304 56.7267 66.0544 56.7831 66.0175C56.8549 65.9546 57.032 65.831 57.3144 65.6466C57.3916 65.6043 57.5023 65.5643 57.6468 65.5264C57.8944 65.4614 58.1219 65.4459 58.3293 65.4797C58.4639 65.4885 58.5415 65.4902 58.5622 65.4848C58.8619 65.4503 59.1029 65.4863 59.2853 65.5928L59.5425 65.6908C59.8379 65.7236 60.0305 65.8274 60.1205 66.0023C60.1367 66.0642 60.1709 66.1104 60.223 66.1409C60.2697 66.1507 60.306 66.1632 60.3321 66.1784L60.5112 66.2307C60.724 66.2851 60.8906 66.3738 61.011 66.4966L61.1998 66.7117C61.2366 66.7682 61.2713 66.8584 61.3038 66.9822L61.3931 67.3227L61.3799 67.5246L61.2769 68.0148C61.2681 68.1494 61.2485 68.2428 61.218 68.2949L61.2262 68.3258C61.2576 68.3617 61.2581 68.4057 61.2277 68.4578C61.2125 68.4838 61.2076 68.5072 61.213 68.5278L61.0775 68.8942L61.0496 69.1661L61.0577 69.1971L61.0496 69.1661L61.0105 69.1433C61.0105 69.1433 61.0002 69.146 60.9795 69.1514C60.9795 69.1514 60.9823 69.1617 60.9877 69.1824C60.942 69.2605 60.9121 69.3566 60.8978 69.4706L60.6791 70.0242L60.2483 71.0304L60.0068 71.6231C59.997 71.6698 59.9295 71.8749 59.8043 72.2386C59.8206 72.3005 59.8162 72.3678 59.7911 72.4406C59.7867 72.5079 59.7796 72.5649 59.7698 72.6116C59.7698 72.6116 59.7725 72.6219 59.7779 72.6425C59.7779 72.6425 59.7676 72.6452 59.747 72.6506C59.7111 72.6821 59.6807 72.7342 59.6557 72.8069C59.6513 72.8742 59.6338 72.9339 59.6034 72.986C59.5425 73.0902 59.5071 73.1657 59.4973 73.2123C59.4571 73.3111 59.4738 73.417 59.5476 73.53C59.5736 73.5452 59.6051 73.5811 59.642 73.6376C59.6788 73.6941 59.7 73.7326 59.7054 73.7533C59.7162 73.7945 59.701 73.8206 59.6597 73.8314L59.5831 73.9177C59.5418 73.9285 59.5239 73.9442 59.5293 73.9649C59.4674 73.9811 59.4212 74.0153 59.3908 74.0674C59.2886 74.1824 59.2039 74.2377 59.1366 74.2333C59.054 74.2549 58.94 74.2407 58.7945 74.1907C58.7012 74.171 58.5665 74.1622 58.3906 74.1643L58.2115 74.112C57.786 74.0031 57.469 73.8877 57.2606 73.7659L57.0262 73.6289C56.8861 73.5995 56.8031 73.5772 56.777 73.5619C56.5426 73.4249 56.4069 73.3282 56.3701 73.2717C56.2236 73.1337 56.1466 72.9664 56.1392 72.7699C56.1067 72.646 56.0927 72.5505 56.0971 72.4832C56.0951 72.3073 56.0984 72.152 56.1072 72.0173C56.0964 71.9761 56.0829 71.9245 56.0666 71.8626C56.071 71.7953 56.083 71.7149 56.1027 71.6216L56.1747 71.1395L56.1894 71.0695L56.1275 71.0857L55.9515 71.2973L55.4608 71.823C55.2869 72.0009 55.1695 72.142 55.1086 72.2462C55.0575 72.3037 55.0195 72.3688 54.9944 72.4415C54.8923 72.5566 54.8184 72.6531 54.7727 72.7313C54.7423 72.7834 54.6912 72.8409 54.6195 72.9038C54.5477 72.9667 54.489 73.0373 54.4434 73.1154C54.4488 73.136 54.4412 73.1491 54.4205 73.1545C54.3999 73.1599 54.382 73.1756 54.3668 73.2017L54.1303 73.5614L53.9395 73.8431C53.7873 74.1035 53.7112 74.2338 53.7112 74.2338C53.609 74.3488 53.4818 74.5365 53.3296 74.797C53.335 74.8176 53.3274 74.8307 53.3067 74.8361L53.2986 74.8051L53.4879 74.3916L53.6396 74.0871C53.6603 74.0817 53.6652 74.0584 53.6543 74.0171L53.6005 74.0643C53.494 74.2466 53.4048 74.3692 53.3331 74.4322C53.2875 74.5103 53.1711 74.7393 52.984 75.1192C52.9383 75.1974 52.8959 75.3298 52.8567 75.5165L52.8191 75.6256C52.8191 75.6256 52.8115 75.6387 52.7963 75.6647C52.7963 75.6647 52.7936 75.6544 52.7881 75.6338C52.7469 75.6446 52.7186 75.663 52.7034 75.6891L52.5679 76.0554C52.5483 76.1488 52.5466 76.2264 52.5628 76.2883L52.6019 76.3112C52.6226 76.3057 52.6302 76.2927 52.6248 76.2721L52.6395 76.2021C52.6753 76.1706 52.7031 76.1082 52.7227 76.0148L52.7978 75.7966L52.8582 75.6485L52.8891 75.6403L52.8972 75.6713L52.7536 76.0067C52.734 76.1001 52.7252 76.2347 52.7273 76.4106C52.712 76.4367 52.7174 76.4573 52.7435 76.4725C52.7695 76.4877 52.7929 76.4927 52.8135 76.4872C52.8961 76.4656 52.9504 76.4624 52.9764 76.4776C53.0177 76.4668 53.041 76.4717 53.0464 76.4923L53.0155 76.5004C52.9329 76.5221 52.884 76.5459 52.8688 76.572L52.815 76.6192L52.8622 76.673L52.9942 76.6714L53.0642 76.6862C53.1207 76.6493 53.1956 76.6407 53.289 76.6603L53.2971 76.6912C53.2971 76.6912 53.2998 76.7015 53.3052 76.7222C53.3052 76.7222 53.2949 76.7249 53.2743 76.7303L53.1195 76.7709L53.0657 76.8181C53.0863 76.8127 53.0994 76.8203 53.1048 76.8409L53.2286 76.8084C53.2492 76.803 53.2856 76.8155 53.3377 76.846L53.2529 76.9013L53.191 76.9175C53.1606 76.9696 53.1454 76.9957 53.1454 76.9957L53.2154 77.0104L53.2854 77.0251L53.1926 77.0495L53.0997 77.0738L53.0459 77.121L53.1159 77.1357L53.1778 77.1195C53.2137 77.088 53.2577 77.0875 53.3098 77.118C53.3771 77.1224 53.4211 77.1219 53.4417 77.1164L53.5655 77.084C53.6274 77.0677 53.6638 77.0803 53.6746 77.1215L53.7446 77.1362L53.8766 77.1347L53.9075 77.1266L54.0004 77.1022L54.3799 77.0358L54.419 77.0586C54.4298 77.0999 54.4456 77.1178 54.4662 77.1124C54.5075 77.1016 54.5384 77.0935 54.5591 77.088C54.6003 77.0772 54.634 77.0794 54.66 77.0946C54.6861 77.1099 54.6991 77.1175 54.6991 77.1175C54.7143 77.0914 54.7192 77.0681 54.7138 77.0474C54.7084 77.0268 54.7057 77.0165 54.7057 77.0165C54.7209 76.9904 54.7285 76.9774 54.7285 76.9774L55.543 76.9292C55.6049 76.913 55.6304 76.8842 55.6196 76.843L55.6033 76.7811L55.6815 76.8267L55.6977 76.8886C55.7444 76.8984 55.7987 76.8952 55.8606 76.879C55.9225 76.8627 55.9768 76.8595 56.0235 76.8693L56.3036 76.9282L56.4436 76.9576C56.4849 76.9468 56.5316 76.9566 56.5837 76.9871L56.6309 77.0409L56.6065 76.948L56.5984 76.917L56.6603 76.9008L56.6994 76.9236C56.72 76.9182 56.7564 76.9307 56.8085 76.9612C56.7672 76.972 56.739 76.9905 56.7237 77.0165C56.6825 77.0273 56.6879 77.048 56.74 77.0784L56.81 77.0931C56.8306 77.0877 56.8437 77.0953 56.8491 77.116C56.8491 77.116 56.8415 77.129 56.8262 77.155C56.811 77.1811 56.8191 77.212 56.8506 77.2479C56.8766 77.2631 56.9 77.268 56.9206 77.2626C56.9771 77.2257 57.0211 77.2252 57.0525 77.2611C57.1046 77.2915 57.1437 77.3144 57.1698 77.3296C57.2479 77.3753 57.3076 77.3927 57.3489 77.3818C57.3695 77.3764 57.3825 77.384 57.388 77.4047C57.3934 77.4253 57.4064 77.4329 57.427 77.4275C57.4477 77.4221 57.458 77.4194 57.458 77.4194C57.5155 77.4705 57.5334 77.4548 57.5118 77.3722L57.5427 77.3641L57.5737 77.356C57.6366 77.4277 57.7462 77.5092 57.9025 77.6006L57.9106 77.6315L57.8796 77.6396L57.8096 77.6249L57.834 77.7178L57.8649 77.7096C57.9421 77.6674 58.0224 77.6794 58.106 77.7457L58.176 77.7604L58.1288 77.7066L58.0816 77.6528L57.9481 77.5224L57.9319 77.4605C57.9471 77.4345 57.9651 77.4187 57.9857 77.4133C58.0063 77.4079 58.0167 77.4052 58.0167 77.4052C58.0535 77.4617 58.0953 77.4948 58.142 77.5047C58.2093 77.509 58.256 77.5189 58.282 77.5341C58.4427 77.5581 58.5523 77.6396 58.6108 77.7787L58.8077 78.0248C58.8077 78.0248 58.8131 78.0454 58.824 78.0867C58.8554 78.1225 58.8635 78.1535 58.8483 78.1795C58.8493 78.2675 58.871 78.35 58.9133 78.4272L58.9605 78.4809L58.9686 78.5119C59.0098 78.5011 59.0359 78.5163 59.0467 78.5576C59.0728 78.5728 59.0885 78.5907 59.0939 78.6113L59.1802 78.688L59.1964 78.7499C59.193 78.9051 59.1837 78.9958 59.1685 79.0219C59.1174 79.0794 59.1 79.1391 59.1162 79.201C59.1531 79.2575 59.2079 79.2982 59.2806 79.3233C59.3273 79.3331 59.3431 79.351 59.3278 79.3771C59.3332 79.3977 59.3256 79.4107 59.305 79.4161C59.2746 79.4682 59.2522 79.5513 59.238 79.6653C59.2434 79.6859 59.2385 79.7092 59.2233 79.7353C59.2027 79.7407 59.2054 79.751 59.2314 79.7663C59.1956 79.7977 59.1857 79.8444 59.202 79.9063C59.2334 79.9422 59.2416 79.9731 59.2263 79.9992C59.2013 80.0719 59.1839 80.1316 59.1741 80.1783C59.1643 80.225 59.1621 80.2586 59.1675 80.2793L59.0777 80.5675L58.9193 80.9729C58.8541 81.1444 58.8241 81.2405 58.8295 81.2611C58.8143 81.2872 58.7691 81.4093 58.694 81.6275L58.588 81.8538C58.5271 81.958 58.5021 82.0307 58.5129 82.072C58.452 82.1762 58.3661 82.3531 58.2551 82.6028C58.1594 82.8264 58.0631 83.006 57.9664 83.1416L57.5016 83.8921L57.1951 84.2372C57.1038 84.3935 57.0222 84.5031 56.9505 84.566C56.8277 84.6864 56.6767 84.8253 56.4974 84.9826C56.3441 85.1551 56.1599 85.3357 55.9448 85.5245C55.6275 85.8283 55.3379 86.0696 55.0761 86.2486C54.9479 86.3484 54.8246 86.4248 54.7062 86.4779C54.6084 86.5256 54.5313 86.5679 54.4748 86.6048C54.4183 86.6417 54.3385 86.6736 54.2353 86.7007L54.0968 86.8032L54.0039 86.8276L53.942 86.8438C53.8909 86.9013 53.7958 86.9593 53.6568 87.0178C53.5384 87.071 53.451 87.1159 53.3945 87.1528L53.3326 87.1691L53.2935 87.1462L53.3244 87.1381L53.3782 87.0909L53.7791 86.8534L53.8329 86.8062C53.8427 86.7596 53.8606 86.7438 53.8867 86.7591C53.8965 86.7124 53.9247 86.6939 53.9714 86.7037C54.0181 86.7136 54.0518 86.7158 54.0724 86.7103C54.1235 86.6528 54.2261 86.5818 54.3804 86.4972L54.4261 86.4191L54.3251 86.4125C54.2892 86.4439 54.2376 86.4575 54.1703 86.4531C54.1084 86.4693 54.0568 86.4828 54.0156 86.4937L53.7304 86.6677C53.6891 86.6785 53.612 86.7208 53.499 86.7946C53.4577 86.8054 53.4295 86.8238 53.4143 86.8499C53.4197 86.8705 53.4121 86.8835 53.3914 86.889L53.4305 86.9118L53.4777 86.9656L53.4467 86.9737C53.3946 86.9433 53.3534 86.9541 53.3229 87.0062L53.1063 87.063C53.0856 87.0684 53.052 87.0662 53.0053 87.0564C52.9846 87.0618 52.9667 87.0775 52.9515 87.1036C52.921 87.1557 52.8749 87.1899 52.813 87.2061C52.7565 87.243 52.7076 87.2668 52.6663 87.2776C52.5892 87.3199 52.4578 87.3654 52.272 87.4141L52.1416 87.5476C52.121 87.553 52.1134 87.566 52.1188 87.5867C52.1394 87.5812 52.1525 87.5889 52.1579 87.6095C52.1785 87.6041 52.1964 87.5884 52.2117 87.5623C52.2323 87.5569 52.2377 87.5775 52.2279 87.6242L52.1432 87.6795L52.0503 87.7039C51.9678 87.7255 51.9422 87.7543 51.9737 87.7901C51.9845 87.8314 51.972 87.8678 51.9361 87.8992C51.9003 87.9307 51.8693 87.9388 51.8433 87.9236ZM52.0924 87.9906C52.087 87.9699 52.074 87.9623 52.0533 87.9677C52.0838 87.9156 52.099 87.8896 52.099 87.8896L52.169 87.9043L52.0924 87.9906ZM53.6243 86.894C53.6037 86.8994 53.5907 86.8918 53.5853 86.8712C53.6059 86.8658 53.6135 86.8528 53.6081 86.8321L53.7319 86.7997L53.6243 86.894ZM51.5617 85.7148C51.6236 85.6985 51.6621 85.6774 51.6774 85.6513L51.7311 85.6041L51.6692 85.6204C51.6073 85.6366 51.5688 85.6578 51.5535 85.6838L51.5226 85.6919L51.5617 85.7148ZM51.5733 85.3809L51.6043 85.3728C51.676 85.3098 51.7428 85.2703 51.8047 85.254L51.8357 85.2459L51.759 85.3322L51.6043 85.3728L51.5733 85.3809ZM51.6256 85.2018C51.6256 85.2018 51.6153 85.2045 51.5946 85.2099C51.5946 85.2099 51.5919 85.1996 51.5865 85.1789L51.6175 85.1708L51.7332 85.1074C51.7538 85.102 51.7668 85.1096 51.7722 85.1302L51.7413 85.1383C51.7261 85.1644 51.6978 85.1828 51.6565 85.1936L51.6256 85.2018ZM52.1401 85.3976C52.2585 85.3445 52.3612 85.2735 52.4481 85.1845L52.5948 85.113C52.6154 85.1076 52.623 85.0945 52.6176 85.0739L52.5867 85.082L52.5557 85.0901C52.4579 85.1378 52.3167 85.23 52.132 85.3667C52.1114 85.3721 52.1038 85.3851 52.1092 85.4057L52.1401 85.3976ZM52.9647 84.8836C53.006 84.8728 53.0625 84.8359 53.1342 84.773L53.0951 84.7502C53.0745 84.7556 53.0462 84.774 53.0104 84.8055C52.9745 84.8369 52.9593 84.863 52.9647 84.8836ZM53.2727 84.6705C53.3346 84.6543 53.3911 84.6174 53.4422 84.5599C53.5139 84.497 53.5677 84.4498 53.6035 84.4183C53.6242 84.4129 53.6318 84.3999 53.6264 84.3792L53.6183 84.3483L53.5873 84.3564L53.395 84.5061C53.2874 84.6005 53.2233 84.6504 53.2027 84.6558L53.1489 84.703L53.2108 84.6867L53.2727 84.6705ZM52.7029 84.3899C52.7235 84.3845 52.7621 84.3633 52.8186 84.3265C52.8957 84.2842 52.9392 84.2397 52.949 84.193L53.0337 84.1377L53.0875 84.0905L53.0565 84.0986L52.9637 84.123L52.949 84.193C52.9077 84.2038 52.8588 84.2277 52.8023 84.2645C52.7458 84.3014 52.6996 84.3356 52.6638 84.367L52.6719 84.398L52.7029 84.3899ZM54.042 84.0717L53.9948 84.0179L53.8953 84.1433L53.9263 84.1352L54.042 84.0717ZM54.0876 83.9936C54.0876 83.9936 54.1029 83.9675 54.1333 83.9154L54.1023 83.9236C54.1023 83.9236 54.0871 83.9496 54.0567 84.0017L54.0876 83.9936ZM54.0765 83.6988C54.1177 83.688 54.133 83.6619 54.1221 83.6206L54.114 83.5897C54.0934 83.5951 54.0858 83.6081 54.0912 83.6288C54.0705 83.6342 54.0629 83.6472 54.0683 83.6678C54.0683 83.6678 54.058 83.6705 54.0374 83.6759C54.0374 83.6759 54.0401 83.6863 54.0455 83.7069L54.0765 83.6988ZM54.5179 83.6161L54.4707 83.5623L54.4398 83.5704L54.3794 83.7186L54.3875 83.7495L54.5179 83.6161ZM54.6417 83.5836C54.6624 83.5782 54.6727 83.5755 54.6727 83.5755C54.6673 83.5548 54.6646 83.5445 54.6646 83.5445L54.6483 83.4826C54.6483 83.4826 54.6277 83.488 54.5864 83.4989C54.5658 83.5043 54.5604 83.4836 54.5702 83.4369C54.5702 83.4369 54.5599 83.4397 54.5392 83.4451C54.5392 83.4451 54.5419 83.4554 54.5474 83.476L54.5326 83.546C54.5326 83.546 54.5353 83.5564 54.5408 83.577C54.5408 83.577 54.5511 83.5743 54.5717 83.5689L54.6027 83.5608C54.6233 83.5553 54.6363 83.563 54.6417 83.5836ZM54.4367 83.3065L54.4286 83.2756C54.4134 83.3016 54.3852 83.3201 54.3439 83.3309C54.3232 83.3363 54.3053 83.352 54.2901 83.3781L54.2982 83.409L54.3373 83.4319L54.4367 83.3065ZM54.7869 83.3801L54.7787 83.3492L54.7087 83.3344L54.6321 83.4207C54.6321 83.4207 54.6348 83.431 54.6402 83.4517C54.6402 83.4517 54.6505 83.449 54.6712 83.4435L54.7869 83.3801ZM54.9939 83.1604L54.9548 83.1376C54.9494 83.1169 54.9364 83.1093 54.9158 83.1147C54.9364 83.1093 54.944 83.0963 54.9386 83.0757C54.9799 83.0648 55.0363 83.028 55.1081 82.965L55.1309 82.926C55.1049 82.9107 55.0506 82.914 54.968 82.9356L54.8995 83.0528L54.8163 83.2401L54.8325 83.302L54.9939 83.1604ZM55.3151 82.7453L55.237 82.6997C55.1957 82.7105 55.1805 82.7365 55.1913 82.7778C55.1967 82.7984 55.1994 82.8088 55.1994 82.8088C55.22 82.8033 55.2304 82.8006 55.2304 82.8006L55.3151 82.7453ZM55.4211 82.519L55.3902 82.5271C55.3489 82.538 55.3337 82.564 55.3445 82.6053C55.3445 82.6053 55.3499 82.6259 55.3608 82.6672L55.3917 82.6591L55.4211 82.519ZM55.5825 82.3774C55.5717 82.3362 55.5456 82.321 55.5044 82.3318L55.4734 82.3399L55.5678 82.4475L55.5825 82.3774ZM55.7814 82.1268C55.7554 82.1116 55.7576 82.0779 55.788 82.0258C55.8293 82.015 55.8445 81.9889 55.8337 81.9477L55.7946 81.9248C55.7794 81.9509 55.7642 81.9769 55.7489 82.003C55.7283 82.0084 55.7104 82.0241 55.6952 82.0502C55.6854 82.0968 55.6625 82.1359 55.6267 82.1674C55.5854 82.1782 55.5702 82.2042 55.581 82.2455L55.6591 82.2912L55.7814 82.1268ZM55.5993 81.8107L55.5292 81.7959L55.4754 81.8431C55.5275 81.8736 55.5536 81.8888 55.5536 81.8888L55.5993 81.8107ZM56.1615 81.4316C56.2234 81.4154 56.2489 81.3866 56.2381 81.3453L56.23 81.3144C56.3125 81.2927 56.356 81.2483 56.3604 81.1809C56.355 81.1603 56.3523 81.15 56.3523 81.15C56.3729 81.1446 56.3832 81.1419 56.3832 81.1419L56.3979 81.0718L56.336 81.0881L56.2138 81.2525L56.2219 81.2834L56.2381 81.3453L56.1762 81.3616L56.1305 81.4397L56.1615 81.4316ZM56.7658 81.3393C56.7963 81.2872 56.8088 81.2508 56.8034 81.2302L56.7953 81.1992L56.7577 81.3083L56.7658 81.3393ZM56.4208 81.0328C56.436 81.0067 56.4746 80.9856 56.5365 80.9693L56.5202 80.9074C56.5507 80.8553 56.5686 80.8396 56.574 80.8602C56.5947 80.8548 56.6126 80.8391 56.6278 80.8131C56.643 80.787 56.6376 80.7664 56.6116 80.7512L56.6035 80.7202L56.5953 80.6892L56.5563 80.6664L56.5025 80.7136C56.5187 80.7755 56.5192 80.8195 56.504 80.8455L56.4045 80.9709C56.4045 80.9709 56.4073 80.9812 56.4127 81.0018C56.4127 81.0018 56.4023 81.0045 56.3817 81.0099L56.4208 81.0328ZM57.0089 80.8785L57.0008 80.8476L56.9323 80.9648L56.9404 80.9957L57.0089 80.8785ZM51.962 78.0339C51.9925 77.9818 52.0077 77.9557 52.0077 77.9557C52.0023 77.9351 51.9893 77.9275 51.9686 77.9329L51.9149 77.9801L51.962 78.0339ZM51.8986 77.9182C51.8878 77.8769 51.89 77.8432 51.9052 77.8172L51.8971 77.7862C51.8971 77.7862 51.8868 77.789 51.8661 77.7944C51.8607 77.7737 51.8607 77.7737 51.8661 77.7944C51.8249 77.8052 51.7885 77.7927 51.7571 77.7568L51.6561 77.7502L51.6251 77.7583L51.6576 77.8821C51.6684 77.9234 51.7048 77.9359 51.7667 77.9197L51.7976 77.9116L51.8058 77.9425L51.8448 77.9654L51.8986 77.9182ZM57.0236 80.8085C57.0236 80.8085 57.0541 80.7564 57.1149 80.6522L57.084 80.6603L57.0155 80.7775L57.0236 80.8085ZM53.4813 78.5286L53.4422 78.5058L53.3103 78.5073L53.2484 78.5235L53.1946 78.5707L53.2646 78.5854C53.3059 78.5746 53.3216 78.5926 53.3118 78.6392L53.3818 78.6539L53.4813 78.5286ZM52.3107 77.9755C52.3313 77.9701 52.3416 77.9674 52.3416 77.9674C52.3362 77.9468 52.3335 77.9364 52.3335 77.9364C52.3335 77.9364 52.3074 77.9212 52.2553 77.8908C52.2553 77.8908 52.258 77.9011 52.2635 77.9217C52.2635 77.9217 52.2531 77.9244 52.2325 77.9298L52.2178 77.9999L52.195 78.0389C52.2362 78.0281 52.2699 78.0303 52.2959 78.0455L52.3107 77.9755ZM56.6572 80.673C56.6779 80.6676 56.6855 80.6546 56.6801 80.6339C56.6486 80.5981 56.6405 80.5671 56.6557 80.5411L56.7633 80.4467L56.8008 80.3376L56.7927 80.3066L56.7065 80.23L56.6999 80.331L56.7161 80.3929L56.6167 80.5182C56.5862 80.5703 56.571 80.5964 56.571 80.5964L56.6572 80.673ZM54.2952 79.1091C54.2952 79.1091 54.2431 79.0787 54.1389 79.0178L54.1617 78.9787C54.1824 78.9733 54.2084 78.9885 54.2399 79.0244C54.2866 79.0342 54.3153 79.0597 54.3261 79.101L54.2952 79.1091ZM51.1953 77.5072C51.1899 77.4865 51.1769 77.4789 51.1563 77.4843C51.0835 77.4593 51.0624 77.4207 51.0928 77.3686C51.0874 77.348 51.095 77.335 51.1157 77.3296C51.1309 77.3035 51.1358 77.2802 51.1304 77.2595C51.1456 77.2335 51.1739 77.215 51.2151 77.2042C51.2564 77.1934 51.2797 77.1983 51.2851 77.2189L51.3471 77.2027L51.3014 77.2808L51.2704 77.289C51.2292 77.2998 51.1955 77.2976 51.1695 77.2824L51.21 77.4371L51.1953 77.5072ZM52.8952 78.1861L52.8561 78.1633L52.8252 78.1714C52.8306 78.192 52.8593 78.2176 52.9114 78.248L52.8952 78.1861ZM52.0894 77.6366L52.1432 77.5894L52.0732 77.5746C52.0678 77.554 52.0547 77.5464 52.0341 77.5518C52.0189 77.5779 51.9749 77.5784 51.9022 77.5533C51.9022 77.5533 51.8631 77.5305 51.785 77.4848L51.7149 77.4701C51.7258 77.5114 51.7312 77.532 51.7312 77.532C51.7312 77.532 51.7339 77.5423 51.7393 77.563C51.7393 77.563 51.7496 77.5603 51.7702 77.5549C51.7909 77.5494 51.8039 77.5571 51.8093 77.5777L51.7784 77.5858C51.7577 77.5912 51.7501 77.6042 51.7555 77.6249C51.7664 77.6662 51.7848 77.6944 51.8108 77.7096L51.8337 77.6706L51.8956 77.6543L51.9656 77.669L52.0894 77.6366ZM50.6585 76.7217L50.6504 76.6907L50.6813 76.6826L50.7985 76.7511C50.8039 76.7717 50.7963 76.7848 50.7757 76.7902L50.6585 76.7217ZM51.6906 77.3773L51.7134 77.3382L51.7362 77.2991C51.7254 77.2578 51.7434 77.2421 51.79 77.2519L51.821 77.2438L51.8829 77.2276L51.9138 77.2195C51.9193 77.2401 51.9116 77.2531 51.891 77.2585C51.8758 77.2846 51.8475 77.303 51.8063 77.3138C51.7856 77.3192 51.7677 77.335 51.7525 77.361L51.6906 77.3773ZM56.9297 80.0722L56.8206 80.0347L56.7831 80.1438L56.8222 80.1666L56.9297 80.0722ZM51.6485 77.0906L51.6941 77.0124C51.6887 76.9918 51.66 76.9662 51.6079 76.9358L51.5688 76.913C51.5231 76.9911 51.4639 77.0177 51.3912 76.9926L51.3374 77.0398L51.4074 77.0545C51.4595 77.085 51.4856 77.1002 51.4856 77.1002C51.5018 77.1621 51.5175 77.18 51.5328 77.154C51.548 77.1279 51.5659 77.1122 51.5866 77.1068L51.6485 77.0906ZM54.1638 78.4819C54.179 78.4559 54.2072 78.4375 54.2485 78.4266L54.2713 78.3876C54.2713 78.3876 54.261 78.3903 54.2404 78.3957C54.2404 78.3957 54.2377 78.3854 54.2323 78.3647C54.1497 78.3864 54.0851 78.3923 54.0384 78.3825L54.0156 78.4216L54.1638 78.4819ZM52.7785 77.4889L52.8095 77.4808L52.7704 77.4579L52.6075 77.4676C52.5662 77.4784 52.538 77.4968 52.5228 77.5229L52.4918 77.531L52.5309 77.5538C52.5515 77.5484 52.5825 77.5403 52.6237 77.5295C52.6596 77.498 52.7036 77.4975 52.7557 77.528L52.7785 77.4889ZM52.1371 77.0616L52.1209 76.9997L52.0443 77.086C52.0855 77.0752 52.1089 77.0801 52.1143 77.1007L52.1371 77.0616ZM52.0427 76.9541L51.9336 76.9165C51.9391 76.9372 51.9211 76.9529 51.8799 76.9637L51.9189 76.9865L52.0427 76.9541ZM52.5035 77.1971L52.4335 77.1824C52.3922 77.1932 52.3743 77.209 52.3797 77.2296L52.4497 77.2443L52.5035 77.1971ZM50.4652 76.1107C50.4391 76.0955 50.4207 76.0673 50.4098 76.026C50.3936 75.9641 50.3931 75.9201 50.4083 75.894C50.429 75.8886 50.4366 75.8756 50.4312 75.855L50.4474 75.9169C50.4636 75.9788 50.4848 76.0174 50.5108 76.0326L50.4961 76.1026C50.4961 76.1026 50.4885 76.1156 50.4733 76.1417C50.4733 76.1417 50.4706 76.1314 50.4652 76.1107ZM53.0961 77.4387C53.1016 77.4593 53.1195 77.4436 53.1499 77.3915L53.0799 77.3768L53.018 77.393L52.9561 77.4092L52.9642 77.4402L53.0961 77.4387ZM50.9472 76.1828L50.9766 76.0427C50.9712 76.0221 50.9582 76.0145 50.9376 76.0199L50.9294 75.9889L50.9147 76.059L50.9457 76.0508L50.8772 76.1681L50.8381 76.1452C50.8533 76.1192 50.8506 76.1089 50.83 76.1143C50.8039 76.0991 50.7882 76.0811 50.7828 76.0605L50.7518 76.0686L50.76 76.0996L50.7681 76.1305C50.7637 76.1978 50.7821 76.2261 50.8234 76.2153L50.9472 76.1828ZM53.1175 77.2677C53.112 77.247 53.1093 77.2367 53.1093 77.2367C53.13 77.2313 53.1403 77.2286 53.1403 77.2286L53.1012 77.2058L52.9546 77.2773L52.8455 77.2398L52.7917 77.2869L52.8617 77.3017L52.9546 77.2773C53.0067 77.3077 53.061 77.3045 53.1175 77.2677ZM56.126 79.0259C56.1043 78.9434 56.0984 78.8787 56.1082 78.8321L56.0691 78.8092L56.0463 78.8483L56.0722 79.0731L56.1113 79.0959L56.126 79.0259ZM54.9117 78.0542L54.9427 78.0461L54.8726 78.0313L54.5941 78.1044C54.542 78.074 54.5159 78.0587 54.5159 78.0587C54.4127 78.0858 54.3563 78.1227 54.3464 78.1694L54.2845 78.1856L54.3546 78.2003C54.4686 78.2145 54.5381 78.1853 54.5631 78.1125C54.5837 78.1071 54.5914 78.0941 54.5859 78.0735C54.5815 78.1408 54.6 78.169 54.6413 78.1582L54.9117 78.0542ZM50.7635 75.7347C50.7842 75.7293 50.7918 75.7163 50.7864 75.6956L50.8401 75.6485L50.8711 75.6403L50.793 75.5947C50.793 75.5947 50.7826 75.5974 50.762 75.6028C50.762 75.6028 50.7647 75.6131 50.7701 75.6337C50.7495 75.6392 50.7419 75.6522 50.7473 75.6728L50.7635 75.7347ZM50.8533 75.4465C50.8533 75.4465 50.843 75.4492 50.8224 75.4546C50.8224 75.4546 50.8197 75.4443 50.8143 75.4237C50.7838 75.4758 50.7686 75.5018 50.7686 75.5018L50.8077 75.5246L50.8533 75.4465ZM51.0096 75.5378L51.0015 75.5069L50.9853 75.445L50.9462 75.4221C50.9157 75.4742 50.9059 75.5209 50.9168 75.5622L50.9721 75.6469L51.0096 75.5378ZM55.9738 77.941C56.0411 77.9454 56.0666 77.9167 56.0504 77.8548C56.0287 77.7722 56.0022 77.713 55.9707 77.6772L55.9626 77.6462C55.8584 77.5853 55.7754 77.563 55.7134 77.5792C55.6722 77.5901 55.6542 77.6058 55.6597 77.6264L55.6678 77.6574L55.5978 77.6427L55.5896 77.6117C55.5321 77.5606 55.4648 77.5562 55.3877 77.5985L55.4039 77.6604L55.3892 77.7304C55.2654 77.7629 55.1698 77.777 55.1025 77.7726L55.0487 77.8197L55.0568 77.8507L55.1888 77.8492L55.2588 77.8639C55.2283 77.916 55.2131 77.942 55.2131 77.942L55.0893 77.9745C55.048 77.9853 55.0301 78.0011 55.0355 78.0217L55.0974 78.0055C55.1647 78.0099 55.2706 77.9931 55.4151 77.9552C55.4097 77.9346 55.4173 77.9216 55.4379 77.9162L55.4689 77.908L55.5308 77.8918C55.5155 77.9179 55.5106 77.9412 55.5161 77.9618C55.5367 77.9564 55.547 77.9537 55.547 77.9537L55.6399 77.9294L55.9738 77.941ZM56.7202 77.3813C56.7094 77.3401 56.6936 77.3221 56.673 77.3276C56.585 77.3286 56.5302 77.2878 56.5086 77.2053C56.3783 77.1291 56.3132 77.0911 56.3132 77.0911C56.3132 77.0911 56.2926 77.0965 56.2513 77.1073L56.2432 77.0764L56.2122 77.0845L56.1975 77.1545L56.2219 77.2474L56.1909 77.2555L56.1828 77.2245C56.198 77.1985 56.1666 77.1626 56.0884 77.117L56.0184 77.1023C55.9034 77.0001 55.771 76.9576 55.6211 76.9749L55.4501 76.9536L55.0624 76.9891L54.8995 76.9987L54.8458 77.0459L54.8848 77.0688L54.932 77.1225L54.9011 77.1307L54.831 77.1159C54.7898 77.1268 54.7718 77.1425 54.7772 77.1631C54.7935 77.225 54.7576 77.2565 54.6697 77.2575L54.6078 77.2738L53.9106 77.3905L53.8339 77.4767C53.8752 77.4659 53.9089 77.4681 53.9349 77.4833L54.0669 77.4818C54.0614 77.4612 54.0691 77.4481 54.0897 77.4427L54.0425 77.3889L54.1125 77.4037C54.1179 77.4243 54.131 77.4319 54.1516 77.4265L54.3845 77.4316L54.4155 77.4234L54.3845 77.4316L54.3698 77.5016L54.4317 77.4854C54.473 77.4745 54.4936 77.4691 54.4936 77.4691L54.5327 77.4919L54.4789 77.5391L54.2932 77.5879L54.2313 77.6041C54.2834 77.6345 54.3094 77.6498 54.3094 77.6498L54.5032 77.632L55.0995 77.5087C55.1407 77.4979 55.1744 77.5001 55.2004 77.5153C55.2265 77.5305 55.2601 77.5327 55.3014 77.5219C55.3938 77.4536 55.4947 77.4602 55.6044 77.5417C55.6348 77.4896 55.6657 77.4815 55.6972 77.5173C55.7439 77.5271 55.7776 77.5293 55.7982 77.5239L55.8291 77.5158C55.8183 77.4745 55.8259 77.4615 55.852 77.4767C55.8726 77.4713 55.8932 77.4659 55.9139 77.4605L55.9758 77.4443C55.9704 77.4236 55.9595 77.3824 55.9433 77.3204C55.9217 77.2379 55.8848 77.1814 55.8327 77.151L55.8165 77.0891L55.8784 77.0728L56.0199 77.2342L56.0281 77.2651L56.0215 77.3661C56.0942 77.3911 56.1306 77.4037 56.1306 77.4037C56.1458 77.3776 56.1615 77.3955 56.1777 77.4575L56.2168 77.4803L56.2787 77.464L56.2315 77.4103L56.2234 77.3793L56.2544 77.3712C56.3065 77.4016 56.3428 77.4142 56.3635 77.4087C56.446 77.3871 56.5187 77.4121 56.5817 77.4838C56.5871 77.5045 56.6028 77.5224 56.6288 77.5376C56.6495 77.5322 56.6625 77.5398 56.6679 77.5605L56.7202 77.3813ZM54.4779 76.7785L54.284 76.7963C54.2634 76.8017 54.2531 76.8044 54.2531 76.8044C54.2477 76.7838 54.245 76.7734 54.245 76.7734L54.2678 76.7344L54.3607 76.71L54.8184 76.6892L54.8574 76.712L54.8265 76.7202L54.4779 76.7785ZM56.4888 77.5082L56.4335 77.4235L56.4025 77.4316L56.3878 77.5016L56.4741 77.5782L56.4888 77.5082ZM57.0246 77.5331C57.0453 77.5276 57.0556 77.5249 57.0556 77.5249C57.0502 77.5043 57.0475 77.494 57.0475 77.494L56.9678 77.3164L56.9287 77.2936L56.9369 77.3245L56.9384 77.4564C56.9438 77.4771 56.9595 77.495 56.9856 77.5102C57.0062 77.5048 57.0192 77.5124 57.0246 77.5331ZM56.7496 77.2413L56.6324 77.1728C56.6432 77.2141 56.6747 77.2499 56.7268 77.2804L56.7496 77.2413ZM57.9405 76.8628C57.9405 76.8628 57.9145 76.8475 57.8624 76.8171L57.9162 76.7699L57.9862 76.7846C57.9558 76.8367 57.9405 76.8628 57.9405 76.8628ZM59.2401 69.0783L59.1701 69.0636L59.1163 69.1108L59.1244 69.1418L59.1472 69.1027L59.2173 69.1174L59.2401 69.0783ZM58.856 68.749C58.8451 68.7078 58.8604 68.6817 58.9016 68.6709L58.8626 68.648C58.8213 68.6589 58.8061 68.6849 58.8169 68.7262C58.8375 68.7208 58.8506 68.7284 58.856 68.749ZM65.6988 71.0564C65.6988 71.0564 65.6961 71.0461 65.6907 71.0255C65.6744 70.9636 65.6739 70.9196 65.6891 70.8936C65.6675 70.811 65.6643 70.7567 65.6795 70.7307C65.7143 70.6113 65.6797 70.5211 65.5755 70.4602C65.518 70.4091 65.5044 70.3576 65.5349 70.3055L65.5577 70.2664L65.6506 70.242C65.6918 70.2312 65.7174 70.2025 65.7272 70.1558C65.7522 70.083 65.7724 70.0336 65.7876 70.0076C65.7974 69.9609 65.7839 69.9093 65.747 69.8528C65.7307 69.7909 65.7096 69.7524 65.6836 69.7371C65.6629 69.7426 65.6423 69.748 65.6217 69.7534C65.6162 69.7327 65.6059 69.7354 65.5907 69.7615C65.5494 69.7723 65.5548 69.793 65.6069 69.8234L65.5922 69.8934C65.5976 69.9141 65.59 69.9271 65.5694 69.9325C65.5488 69.9379 65.5205 69.9563 65.4846 69.9878C65.4694 70.0139 65.4699 70.0578 65.4862 70.1197L65.4552 70.1279L65.408 70.0741C65.3918 70.0122 65.3913 69.9682 65.4065 69.9421C65.4978 69.7859 65.5354 69.6768 65.5192 69.6149C65.4975 69.5323 65.4943 69.478 65.5095 69.452C65.5139 69.3846 65.5276 69.2267 65.5506 68.978L65.5948 68.768C65.4916 68.795 65.4356 68.8759 65.4268 69.0105C65.4072 69.1039 65.4055 69.1815 65.4217 69.2434L65.3613 69.3916L65.3304 69.3997C65.325 69.3791 65.312 69.3715 65.2913 69.3769C65.2859 69.3562 65.2908 69.3329 65.306 69.3068C65.2932 69.0897 65.2939 68.9241 65.3081 68.8101L65.3228 68.74C65.3174 68.7194 65.3043 68.7118 65.2837 68.7172C65.2945 68.7585 65.2923 68.7921 65.2771 68.8182L65.1482 69.0836L65.1107 69.1927C65.1053 69.172 65.1124 69.115 65.132 69.0217L65.1665 68.6487L65.1812 68.5787C65.1812 68.5787 65.1709 68.5814 65.1503 68.5868C65.1448 68.5662 65.1525 68.5531 65.1731 68.5477C65.1883 68.5217 65.1932 68.4983 65.1878 68.4777C65.177 68.4364 65.1689 68.4055 65.1635 68.3849L65.1295 68.1291C65.1339 68.0618 65.1437 68.0151 65.1589 67.9891C65.1687 67.9424 65.1812 67.906 65.1964 67.88L65.3893 67.1016L65.4496 66.9534C65.3539 67.177 65.2761 67.3849 65.2162 67.577C65.1716 67.7431 65.1318 67.8859 65.097 68.0053C65.0807 67.9434 65.0802 67.8994 65.0955 67.8734C65.1347 67.6866 65.1538 67.5493 65.1528 67.4613C65.1616 67.3267 65.1758 67.2127 65.1954 67.1193C65.215 67.026 65.2347 66.9326 65.2543 66.8392L65.2269 66.4825C65.2161 66.4412 65.2205 66.3739 65.2401 66.2806C65.2989 66.0005 65.3306 65.8267 65.335 65.7594C65.3394 65.6921 65.3438 65.6248 65.3482 65.5575C65.3526 65.4902 65.3673 65.4201 65.3923 65.3474C65.4349 65.0054 65.5476 64.6781 65.7303 64.3655L65.9327 63.75L66.122 63.3365C66.2231 63.1335 66.3081 62.8686 66.3767 62.5419L66.3803 62.177C66.3891 62.0424 66.4348 61.9642 66.5173 61.9426L66.8887 61.8452L67.3221 61.7315C67.3329 61.7728 67.3747 61.8059 67.4474 61.831C67.5147 61.8353 67.5403 61.8066 67.524 61.7447C67.5186 61.7241 67.5159 61.7137 67.5159 61.7137C67.5365 61.7083 67.5496 61.7159 67.555 61.7366L68.0614 61.9015C68.1548 61.9211 68.2275 61.9461 68.2796 61.9766C68.3317 62.007 68.3811 62.0272 68.4277 62.037L68.514 62.1136C68.5401 62.1288 68.5585 62.1571 68.5693 62.1983C68.5954 62.2136 68.6344 62.2364 68.6865 62.2668C68.7028 62.3287 68.7266 62.3776 68.7581 62.4135L68.8459 62.622C68.8719 62.6373 68.8827 62.6785 68.8783 62.7458C68.8892 62.7871 68.8973 62.8181 68.9027 62.8387L68.8895 63.0407L68.8159 63.3908C68.7953 63.3962 68.7904 63.4195 68.8012 63.4608C68.812 63.5021 68.7995 63.5384 68.7637 63.5699C68.7072 63.6068 68.6099 63.6985 68.4719 63.8449C68.4164 63.9698 68.3609 64.0946 68.3054 64.2194C68.2446 64.3236 68.1967 64.4354 68.1618 64.5548C68.015 64.8359 67.8867 65.1453 67.7767 65.4829L67.6559 65.7792C67.6407 65.8053 67.6184 65.8883 67.589 66.0284L67.3018 66.6992L67.2429 66.9793L67.1074 67.3457C67.0824 67.4184 67.0421 67.5172 66.9866 67.642C66.9518 67.7614 66.9093 67.8938 66.8593 68.0393C66.8136 68.1174 66.7837 68.2135 66.7695 68.3275C66.7695 68.3275 66.7319 68.4366 66.6568 68.6548L66.5 69.1922L66.366 69.6905L66.2387 70.0878L66.1717 70.3369L65.9905 70.7814L65.9611 70.9215C66.0186 70.9726 65.9958 71.0116 65.8926 71.0387C65.8926 71.0387 65.885 71.0517 65.8698 71.0778C65.8698 71.0778 65.8568 71.0701 65.8307 71.0549L65.6988 71.0564ZM65.9073 70.9687L65.9434 70.7276L65.9271 70.6657C65.8815 70.7439 65.8515 70.8399 65.8373 70.9539C65.8221 70.98 65.8172 71.0033 65.8226 71.024C65.8432 71.0186 65.8639 71.0131 65.8845 71.0077L65.9073 70.9687ZM65.8398 69.8285L65.8596 69.5255C65.8292 69.5776 65.814 69.6037 65.814 69.6037C65.8336 69.5103 65.8174 69.4484 65.7653 69.418C65.7446 69.4234 65.737 69.4364 65.7424 69.457C65.7066 69.4885 65.6837 69.5276 65.6739 69.5743C65.6847 69.6155 65.6825 69.6492 65.6673 69.6752L65.7373 69.69C65.758 69.6845 65.7737 69.7025 65.7845 69.7437L65.7698 69.8138L65.7779 69.8447L65.8398 69.8285ZM75.6928 84.5463C75.6657 84.4431 75.6571 84.3682 75.6669 84.3215C75.6767 84.2748 75.6632 84.2232 75.6263 84.1667C75.5894 84.1102 75.5759 84.0586 75.5857 84.0119C75.5955 83.9653 75.582 83.9137 75.5451 83.8572C75.5343 83.8159 75.5338 83.7719 75.5436 83.7253L75.4137 83.23C75.4083 83.2094 75.3898 83.1811 75.3584 83.1453C75.3323 83.13 75.3166 83.1121 75.3112 83.0915C75.2851 83.0763 75.264 83.0377 75.2477 82.9758C75.2261 82.8932 75.1995 82.834 75.1681 82.7982L75.1518 82.7363C75.1464 82.7156 75.141 82.695 75.1356 82.6744C75.1508 82.6483 75.153 82.6147 75.1422 82.5734L75.126 82.5115L75.1894 82.6272L75.1828 82.7282L75.1909 82.7591L75.2219 82.751C75.2198 82.5751 75.2053 82.4355 75.1782 82.3324L75.1701 82.3014C75.1647 82.2808 75.1463 82.2525 75.1148 82.2167C75.104 82.1754 75.1089 82.1521 75.1295 82.1467C75.16 82.0946 75.1568 82.0403 75.1199 81.9838C75.0884 81.9479 75.0673 81.9093 75.0565 81.8681C75.0771 81.8627 75.0744 81.8523 75.0483 81.8371C75.0429 81.8165 75.0402 81.8062 75.0402 81.8062C75.0849 81.6401 75.0605 81.5472 74.9671 81.5276C74.889 81.4819 74.8548 81.4357 74.8646 81.3891C74.8951 81.337 74.9103 81.3109 74.9103 81.3109L74.8504 80.8304C74.843 80.6338 74.822 80.3857 74.7875 80.086L74.7439 79.6674C74.7439 79.6674 74.7412 79.6571 74.7358 79.6364C74.7358 79.6364 74.7255 79.6391 74.7048 79.6445L74.7129 79.6755C74.652 79.7797 74.6216 79.8318 74.6216 79.8318L74.6135 79.8008L74.5972 79.7389C74.5668 79.791 74.5516 79.8171 74.5516 79.8171C74.533 79.9984 74.5426 80.1613 74.5805 80.3057L74.5967 80.3676C74.5791 80.6369 74.5763 80.8361 74.5881 80.9654L74.5714 81.5322C74.5561 81.5582 74.5463 81.6049 74.5419 81.6722C74.5375 81.7395 74.538 81.7835 74.5434 81.8041L74.5612 81.998C74.5578 82.1532 74.568 82.3601 74.5916 82.6186L74.5866 82.8515L74.5947 82.8824L74.5866 82.8515L74.5622 82.7586C74.5243 82.6142 74.5201 82.4719 74.5495 82.3319C74.5225 82.2287 74.5138 82.1538 74.5237 82.1071C74.4858 81.9626 74.4793 81.854 74.5044 81.7813C74.5196 81.7553 74.5137 81.6906 74.4866 81.5875L74.4724 81.0288C74.4453 80.9256 74.4308 80.7861 74.4288 80.6102L74.4125 80.5483C74.4071 80.5276 74.4093 80.494 74.4191 80.4473C74.4289 80.4006 74.4208 80.3696 74.3948 80.3544C74.41 80.3284 74.4046 80.3077 74.3785 80.2925C74.3525 80.2773 74.3395 80.2697 74.3395 80.2697L74.276 80.154C74.2804 80.0867 74.2821 80.009 74.2811 79.9211C74.2855 79.8538 74.2769 79.7788 74.2552 79.6963C74.2542 79.6083 74.2294 79.4715 74.1806 79.2858L74.137 78.8672L74.0802 78.6505L74.0152 78.4029C73.9936 78.3203 73.9763 78.1705 73.9635 77.9533L73.9554 77.9223C73.9554 77.9223 73.945 77.925 73.9244 77.9304C73.9244 77.9304 73.9271 77.9408 73.9325 77.9614C73.9227 78.0081 73.9156 78.0651 73.9112 78.1324C73.9014 78.1791 73.8943 78.2361 73.8899 78.3034C73.9048 78.6965 73.8953 78.9967 73.8615 79.2041L73.8874 79.4289C73.8928 79.4495 73.8852 79.4625 73.8645 79.4679L73.8564 79.437L73.8549 79.3051C73.8549 79.3051 73.8446 79.3078 73.8239 79.3132C73.8239 79.3132 73.8212 79.3029 73.8158 79.2822L73.8239 79.3132L73.8107 79.5151C73.827 79.577 73.8253 79.6547 73.8057 79.748C73.8067 79.836 73.8126 79.9006 73.8234 79.9419L73.8315 79.9728L73.8234 79.9419L73.8138 79.779C73.803 79.7377 73.7872 79.7198 73.7666 79.7252C73.7666 79.7252 73.7563 79.7279 73.7356 79.7333C73.7356 79.7333 73.7383 79.7436 73.7438 79.7643L73.7696 79.9891C73.7598 80.0358 73.7657 80.1004 73.7874 80.1829L73.7757 80.5168L73.7869 80.8116C73.8106 81.0701 73.8207 81.2769 73.8173 81.4322L73.8254 81.4631L73.8173 81.4322L73.6925 80.704L73.6976 80.4711C73.6813 80.4092 73.6651 80.3473 73.6489 80.2854C73.6533 80.2181 73.6343 80.1459 73.592 80.0687L73.5352 79.8521L73.5271 79.8211L73.5352 79.8521L73.5235 80.186L73.4814 79.8993C73.502 79.8938 73.4993 79.8835 73.4733 79.8683L73.4814 79.8993C73.477 79.9666 73.4753 80.0442 73.4763 80.1322C73.4774 80.2201 73.468 80.3108 73.4484 80.4041C73.4538 80.4248 73.4462 80.4378 73.4256 80.4432C73.405 80.4486 73.3946 80.4513 73.3946 80.4513L73.3865 80.4204C73.3909 80.3531 73.3926 80.2754 73.3916 80.1875C73.3906 80.0995 73.3847 80.0349 73.3738 79.9936L73.3256 79.1792L73.3145 78.8844C73.3145 78.8844 73.3091 78.8638 73.2982 78.8225C73.308 78.7758 73.2923 78.7579 73.251 78.7687L73.2348 78.7068L73.2318 78.4429C73.2209 78.4017 73.2052 78.3837 73.1846 78.3892L73.1927 78.4201C73.1829 78.4668 73.1861 78.5211 73.2023 78.583L73.1729 78.723C73.1783 78.7437 73.1707 78.7567 73.1501 78.7621L73.142 78.7312L73.1227 78.4054L73.1064 78.3435L73.0836 78.3826C73.089 78.4032 73.0814 78.4162 73.0608 78.4216L73.0851 78.5145L73.0608 78.4216L72.9933 77.2814L72.9984 77.0485L72.9902 77.0176C72.9902 77.0176 72.9799 77.0203 72.9593 77.0257C72.9593 77.0257 72.962 77.036 72.9674 77.0567L72.9963 77.5453C72.9757 77.5507 72.9681 77.5637 72.9735 77.5844L72.9654 77.5534L72.9573 77.5225L72.9329 77.4296C72.9177 77.4557 72.9155 77.4893 72.9263 77.5306L72.8984 77.8026C72.8984 77.8026 72.8881 77.8053 72.8674 77.8107C72.8674 77.8107 72.8701 77.821 72.8756 77.8416L72.8593 77.7797L72.8497 77.6169L72.8304 77.2911L72.8223 77.2601L72.8076 77.3302L72.7913 77.2683L72.7543 76.7486C72.7015 76.2111 72.6628 75.7691 72.6381 75.4227L72.4828 74.074L72.423 73.5935C72.4067 73.5316 72.378 73.506 72.3367 73.5169C72.1618 73.6068 71.8734 73.7266 71.4715 73.8761C71.3477 73.9086 71.188 73.9725 70.9925 74.0679L69.7559 74.5246C69.3953 74.6633 69.1276 74.7776 68.9527 74.8676C68.9114 74.8784 68.8679 74.9229 68.8223 75.0011C68.6233 75.2517 68.4537 75.5719 68.3133 75.9616L68.2138 76.0869C68.1127 76.2899 67.9436 76.6541 67.7064 77.1794C67.5552 77.5279 67.4546 77.7748 67.4045 77.9203C67.3893 77.9463 67.3441 78.0684 67.269 78.2866L67.2543 78.3567C67.2966 78.4338 67.2819 78.5038 67.2101 78.5667L67.1579 78.7459L66.9996 79.1513C67.0104 79.1926 66.9952 79.2186 66.9539 79.2294C66.9082 79.3076 66.8854 79.3466 66.8854 79.3466C66.7995 79.5236 66.7075 79.8454 66.6093 80.3123C66.5941 80.3383 66.5821 80.4187 66.5733 80.5533L66.5586 80.6233L66.5424 80.5614L66.5099 80.4376L66.5723 79.7927L66.548 79.6998C66.5165 79.664 66.5133 79.6097 66.5383 79.5369C66.5589 79.5315 66.5693 79.5288 66.5693 79.5288C66.5639 79.5082 66.5611 79.4979 66.5611 79.4979C66.5808 79.4045 66.5896 79.2699 66.5875 79.0939C66.6028 79.0679 66.5995 79.0136 66.5779 78.9311C66.5562 78.8485 66.5606 78.7812 66.5911 78.7291L66.8915 77.8563L66.9209 77.7163L66.8215 77.8416C66.7856 77.8731 66.7655 77.9225 66.7611 77.9898C66.736 78.0625 66.7159 78.1119 66.7007 78.138C66.6202 78.3355 66.5468 78.4761 66.4805 78.5596L66.451 78.6997L66.4135 78.8088C66.3722 78.8196 66.3543 78.8353 66.3597 78.856L66.3206 78.8331C66.3511 78.781 66.3663 78.755 66.3663 78.755C66.3869 78.7496 66.3973 78.7469 66.3973 78.7469C66.3918 78.7262 66.3891 78.7159 66.3891 78.7159C66.3729 78.654 66.3974 78.5373 66.4627 78.3658C66.5128 78.2203 66.5324 78.127 66.5216 78.0857C66.5304 77.9511 66.5348 77.8837 66.5348 77.8837C66.5554 77.8783 66.5657 77.8756 66.5657 77.8756C66.5397 77.8604 66.5266 77.8528 66.5266 77.8528C66.506 77.8582 66.4984 77.8712 66.5038 77.8919C66.4744 78.0319 66.4194 78.2007 66.3389 78.3983L66.3242 78.4683C66.3154 78.6029 66.2985 78.7066 66.2734 78.7793C66.2484 78.8521 66.1907 79.0106 66.1004 79.2548C66.1058 79.2754 66.1085 79.2857 66.1085 79.2857C66.0879 79.2912 66.0776 79.2939 66.0776 79.2939L66.0695 79.2629L66.0989 79.1229C66.0556 78.9578 66.0818 78.7634 66.1775 78.5398C66.258 78.3423 66.3054 78.1865 66.3196 78.0725C66.3132 77.9639 66.3355 77.8809 66.3866 77.8233L66.4176 77.8152C66.3861 77.7794 66.3883 77.7457 66.4241 77.7143C66.4394 77.6882 66.4546 77.6622 66.4698 77.6361L66.4683 77.5042C66.4987 77.4521 66.5113 77.4157 66.5058 77.3951L66.4977 77.3641L66.4668 77.3722L66.3983 77.4895C66.3841 77.6035 66.3384 77.6816 66.2613 77.7239C66.22 77.7347 66.1923 77.7971 66.178 77.9111L66.1243 77.9583L66.139 77.8883C66.1434 77.821 66.1706 77.7146 66.2207 77.5691C66.287 77.4856 66.3365 77.2961 66.3694 77.0008L66.3841 76.9308L66.3988 76.8608L66.345 76.908C66.2689 77.0382 66.0921 77.4154 65.8147 78.0395L65.7919 78.0786L65.7757 78.0167L66.0481 77.4159L66.0613 77.2139L65.9913 77.1992C65.9707 77.2046 65.9451 77.2334 65.9147 77.2855C65.9201 77.3061 65.9255 77.3267 65.9309 77.3474C65.9103 77.3528 65.8924 77.3685 65.8771 77.3946L65.8447 77.2708C65.8751 77.2187 65.9002 77.1459 65.9198 77.0526C65.9654 76.9744 65.9546 76.9332 65.8873 76.9288L65.8563 76.9369L65.8026 76.9841L65.8173 76.914C65.8369 76.8207 65.8619 76.7479 65.8924 76.6958L65.9741 76.3767L66.1258 76.0722L66.3836 75.5415L66.55 75.167L66.6104 75.0188L66.5941 74.9569C66.5268 74.9525 66.5008 74.9373 66.516 74.9112C66.5312 74.8852 66.5465 74.8591 66.5617 74.8331L66.5845 74.794L66.6073 74.7549L66.6236 74.8169L66.6317 74.8478L66.6627 74.8397C66.6779 74.8136 66.6931 74.7876 66.7083 74.7615C66.7442 74.7301 66.78 74.6986 66.8159 74.6672L66.8453 74.5271L66.8372 74.4962L66.7672 74.4814C66.7726 74.5021 66.7574 74.5281 66.7215 74.5596L66.723 74.6915C66.723 74.6915 66.7024 74.6969 66.6611 74.7078L66.653 74.6768C66.7183 74.5053 66.7586 74.4065 66.7738 74.3805C66.7836 74.3338 66.8037 74.2844 66.8342 74.2323C66.8646 74.1802 66.8847 74.1308 66.8945 74.0841C66.9304 74.0527 66.9581 73.9903 66.9778 73.8969C67.0224 73.7308 67.0497 73.6244 67.0595 73.5777L67.0204 73.5549C67.0204 73.5549 67.0101 73.5576 66.9894 73.563C66.9894 73.563 66.9867 73.5527 66.9813 73.5321L66.9651 73.4701L67.0189 73.423L67.1006 73.1038L67.2457 72.9003L67.6684 71.8631L67.8886 71.4415L68.1235 70.9498L68.1464 70.9107L68.1301 70.8488C68.1095 70.8542 68.1019 70.8672 68.1073 70.8879L67.8724 71.3796L67.7501 71.544C67.7555 71.5646 67.7479 71.5776 67.7272 71.583L67.711 71.5211L67.7861 71.3029C67.7807 71.2823 67.778 71.272 67.778 71.272C67.7932 71.2459 67.7878 71.2253 67.7618 71.2101L67.7536 71.1791C67.7939 71.0803 67.8238 70.9843 67.8434 70.8909C67.8783 70.7715 67.9158 70.6624 67.9561 70.5636C68.1682 70.111 68.2743 69.8847 68.2743 69.8847L68.4473 69.4092C68.5268 69.1237 68.6274 68.8768 68.7492 68.6684L69.0268 67.8347C69.067 67.7359 69.1149 67.6241 69.1704 67.4993C69.2259 67.3745 69.2835 67.216 69.3434 67.0238L69.6291 66.2211C69.7543 65.8574 69.8218 65.6523 69.8316 65.6056C69.8925 65.5014 69.9376 65.3793 69.967 65.2392C70.0367 65.0004 70.102 64.8289 70.1629 64.7247C70.2032 64.6259 70.2483 64.5038 70.2984 64.3583C70.3485 64.2129 70.3931 64.0468 70.4324 63.86C70.4466 63.746 70.4993 63.6109 70.5907 63.4546C70.682 63.2983 70.7505 63.1811 70.7962 63.103L70.8956 62.9776C70.9261 62.9255 70.9826 62.8887 71.0651 62.867C71.1477 62.8454 71.2069 62.8188 71.2427 62.7873C71.397 62.7028 71.4947 62.6551 71.536 62.6442C71.6186 62.6226 71.7271 62.6162 71.8618 62.625C71.9085 62.6348 71.9834 62.6261 72.0866 62.5991C72.1278 62.5883 72.1794 62.5747 72.2413 62.5585C72.3032 62.5423 72.3472 62.5417 72.3733 62.557C72.3993 62.5722 72.433 62.5744 72.4742 62.5636C72.5416 62.568 72.6295 62.567 72.7381 62.5605C72.8673 62.5487 72.9786 62.5526 73.072 62.5722C73.1501 62.6179 73.2826 62.6603 73.4693 62.6996L73.7103 62.7356L73.8357 62.835C73.9236 62.834 73.9833 62.8515 74.0148 62.8873C74.0615 62.8971 74.0951 62.8993 74.1158 62.8939L74.2249 62.9315L74.5308 63.2151L74.5471 63.277L74.4476 63.4024C74.3867 63.5065 74.3595 63.6129 74.3659 63.7215C74.4092 63.8866 74.4368 64.0338 74.4486 64.163C74.4605 64.2922 74.4669 64.4008 74.4679 64.4887L74.5684 65.124L74.6638 65.9923L74.7333 66.6357C74.8003 67.0592 74.8456 67.4002 74.8693 67.6586C74.8757 67.7672 74.8848 67.8861 74.8967 68.0154C74.9031 68.1239 74.9095 68.2325 74.916 68.3411C74.9322 68.403 74.9381 68.4676 74.9337 68.535C74.9239 68.5816 74.9271 68.6359 74.9434 68.6978L74.9302 68.8998C74.9007 69.0399 74.8784 69.1229 74.8632 69.1489L74.8485 69.219C74.819 69.359 74.8476 69.5941 74.9342 69.9243C74.9396 69.9449 74.963 69.9498 75.0042 69.939L75.0971 69.9147L75.0124 69.97C75.0178 69.9906 75.0102 70.0036 74.9895 70.009C74.9689 70.0144 74.9613 70.0275 74.9667 70.0481C74.9775 70.0894 74.9932 70.1073 75.0139 70.1019C75.0497 70.0704 75.0677 70.0547 75.0677 70.0547L75.0986 70.0466L75.1067 70.0775L75.0839 70.1166L75.1539 70.1313C75.1898 70.0999 75.249 70.0733 75.3315 70.0517L75.3934 70.0354C75.3728 70.0408 75.3652 70.0539 75.3706 70.0745L75.224 70.146L75.2011 70.1851L75.2321 70.177L75.6116 70.1105L75.7664 70.0699C75.787 70.0645 75.8077 70.0591 75.8283 70.0537C75.8696 70.0429 75.9032 70.0451 75.9293 70.0603C75.9553 70.0755 76.0096 70.0723 76.0922 70.0506L76.4864 69.9142L76.5483 69.8979L76.4945 69.9451C76.3816 70.0188 76.2838 70.0665 76.2013 70.0882C76.1806 70.0936 76.173 70.1066 76.1784 70.1273L76.2094 70.1191L76.3641 70.0786L76.4032 70.1014L76.3723 70.1095C76.3364 70.141 76.2875 70.1648 76.2256 70.1811L75.7238 70.4119C75.7238 70.4119 75.7265 70.4223 75.7319 70.4429C75.7319 70.4429 75.7216 70.4456 75.7009 70.451L75.7319 70.4429L76.3738 70.2414C76.4976 70.209 76.5877 70.1743 76.6442 70.1374L76.7143 70.1521L76.6524 70.1684L76.2972 70.3277C76.2765 70.3331 76.2124 70.383 76.1048 70.4774C75.9919 70.5511 75.8838 70.6015 75.7806 70.6286C75.7447 70.6601 75.6855 70.6866 75.603 70.7083L75.6111 70.7392L75.8359 70.7133C75.8565 70.7079 75.8642 70.6949 75.8587 70.6743C75.8892 70.6222 75.9278 70.601 75.9744 70.6108C76.0157 70.6 76.0467 70.5919 76.0673 70.5865C76.0879 70.5811 76.101 70.5887 76.1064 70.6093L76.0754 70.6174C76.0808 70.6381 76.0732 70.6511 76.0526 70.6565L76.0835 70.6484C76.1042 70.643 76.1172 70.6506 76.1226 70.6712L76.1307 70.7022C76.1514 70.6968 76.1617 70.6941 76.1617 70.6941C76.1563 70.6734 76.1536 70.6631 76.1536 70.6631L76.2073 70.6159L76.6864 70.4241C76.8102 70.3916 76.9003 70.357 76.9568 70.3201L76.9959 70.3429L76.9649 70.351C76.9703 70.3717 76.9627 70.3847 76.9421 70.3901L76.973 70.382L77.4292 70.2293L77.654 70.2034C77.6334 70.2088 77.6258 70.2218 77.6312 70.2425C77.5432 70.2435 77.471 70.2624 77.4145 70.2993C77.3732 70.3101 77.3423 70.3182 77.3216 70.3236C77.2652 70.3605 77.1647 70.3979 77.0202 70.4358C76.9583 70.452 76.9122 70.4862 76.8817 70.5383L76.8508 70.5464L76.7889 70.5626C76.7269 70.5789 76.6781 70.6027 76.6422 70.6342C76.6063 70.6656 76.5678 70.6868 76.5265 70.6976L76.4727 70.7448C76.4934 70.7394 76.5064 70.747 76.5118 70.7676C76.5324 70.7622 76.5455 70.7698 76.5509 70.7905L76.5199 70.7986L76.489 70.8067L76.4271 70.823L76.4514 70.9158L76.5133 70.8996L76.7447 70.7727C76.7914 70.7825 76.843 70.769 76.8995 70.7321C76.956 70.6953 76.9945 70.6741 77.0152 70.6687C77.0358 70.6633 77.0461 70.6606 77.0461 70.6606L77.108 70.6443C77.1134 70.665 77.0955 70.6807 77.0542 70.6915C76.9 70.7761 76.7609 70.8346 76.6371 70.8671L76.5605 70.9534C76.5399 70.9588 76.5323 70.9718 76.5377 70.9924L76.5686 70.9843L76.971 70.8788L77.072 70.8854L77.1029 70.8772L77.4972 70.7408C77.6623 70.6975 77.7731 70.6574 77.8296 70.6205L78.1 70.5165L78.5171 70.3409L78.579 70.3247L78.6491 70.3394L78.5872 70.3556L78.1163 70.5784L77.823 70.7215L77.7692 70.7687L77.8311 70.7524L78.0087 70.6728C78.1944 70.624 78.4263 70.5412 78.7044 70.4241C78.8076 70.3971 78.9363 70.3412 79.0905 70.2567L79.5695 70.0649C79.6934 70.0324 79.7835 69.9977 79.84 69.9608C79.8813 69.95 79.884 69.9603 79.8481 69.9918C79.8481 69.9918 79.8508 70.0021 79.8562 70.0228C79.8562 70.0228 79.8666 70.02 79.8872 70.0146C79.9078 70.0092 79.9154 69.9962 79.91 69.9756L80.5829 69.766L81.5181 69.4215L81.7657 69.3565L81.7966 69.3484C81.776 69.3538 81.7684 69.3668 81.7738 69.3875L81.5343 69.4834L80.9477 69.7696L80.5616 69.937C80.479 69.9587 80.4095 69.9879 80.353 70.0248C80.0956 70.1364 79.9131 70.2394 79.8055 70.3338L79.2189 70.62L78.4694 70.9158L77.8519 71.2101L77.2572 71.4654L76.7554 71.6962L75.636 72.2214C75.6001 72.2529 75.5539 72.287 75.4974 72.3239C75.4355 72.3401 75.3867 72.364 75.3508 72.3955C75.3095 72.4063 75.2943 72.4323 75.3051 72.4736L75.3406 72.8613L75.3615 73.319C75.3777 73.3809 75.3706 73.4379 75.3401 73.49C75.3401 73.49 75.3298 73.4927 75.3092 73.4981C75.3092 73.4981 75.3119 73.5084 75.3173 73.529L75.3092 73.4981L75.2833 73.2733L75.2574 73.0485L75.264 72.9475L75.2316 72.8237L75.1631 72.9409L75.1549 72.91C75.1289 72.8948 75.1077 72.8562 75.0915 72.7943L75.0834 72.7633L75.0606 72.8024L75.0783 72.9962C75.0847 73.1048 75.1123 73.252 75.161 73.4377C75.1458 73.4638 75.1409 73.4871 75.1463 73.5077C75.1669 73.5023 75.1849 73.4866 75.2001 73.4605C75.2207 73.4551 75.2234 73.4654 75.2082 73.4915L75.1625 73.5696C75.1375 73.6424 75.1282 73.733 75.1346 73.8416C75.1563 73.9242 75.1725 73.9861 75.1833 74.0273C75.2754 74.3781 75.3224 74.6415 75.3244 74.8174L75.3985 75.8566C75.4049 75.9652 75.4129 76.2057 75.4223 76.5782C75.445 76.7487 75.4546 76.9115 75.4513 77.0668C75.4425 77.2015 75.4413 77.3231 75.4477 77.4317C75.4778 77.7987 75.4841 78.1168 75.4665 78.3861C75.4489 78.6554 75.4487 78.865 75.466 79.0148C75.468 79.1907 75.4798 79.32 75.5015 79.4025C75.5123 79.4438 75.5177 79.4644 75.5177 79.4644C75.5546 79.5209 75.5632 79.5958 75.5436 79.6892L75.5319 80.0231L75.4827 80.4661C75.4989 80.528 75.5021 80.5823 75.4923 80.6289C75.4812 81.0068 75.4783 81.2061 75.4837 81.2267C75.4685 81.2527 75.469 81.2967 75.4852 81.3586L75.4868 81.4906C75.505 81.7284 75.5043 81.894 75.4847 81.9873C75.4976 82.2045 75.5175 82.3647 75.5446 82.4679L75.6141 83.1113C75.6358 83.1938 75.6471 83.2791 75.6481 83.367C75.6491 83.455 75.6577 83.5299 75.674 83.5918C75.6848 83.6331 75.6831 83.7107 75.6689 83.8247C75.6807 83.9539 75.7105 84.0674 75.7582 84.1652L75.7663 84.1961C75.7251 84.207 75.7071 84.2227 75.7125 84.2433C75.7234 84.2846 75.7315 84.3156 75.7369 84.3362C75.7173 84.4296 75.7156 84.5072 75.7318 84.5691L75.7009 84.5772L75.6928 84.5463ZM66.107 77.1358L66.1364 76.9957L66.1283 76.9648C66.1077 76.9702 66.1001 76.9832 66.1055 77.0039C66.075 77.056 66.0625 77.0923 66.0679 77.113L66.0761 77.1439L66.107 77.1358ZM74.9864 81.8534C74.9658 81.8588 74.9474 81.8305 74.9311 81.7686L74.9296 81.6367L74.9606 81.6286C74.9768 81.6905 74.9773 81.7345 74.9621 81.7605L74.9864 81.8534ZM73.4621 79.5735C73.4567 79.5529 73.454 79.5425 73.454 79.5425C73.4746 79.5371 73.485 79.5344 73.485 79.5344C73.4633 79.4519 73.4623 79.3639 73.4819 79.2706L73.4657 79.2087L73.4576 79.1777L73.4347 79.2168L73.454 79.5425L73.4621 79.5735ZM73.7503 79.6633C73.771 79.6579 73.7965 79.6291 73.827 79.577C73.8063 79.5825 73.7933 79.5748 73.7879 79.5542C73.7825 79.5336 73.7798 79.5233 73.7798 79.5233C73.7385 79.5341 73.726 79.5704 73.7422 79.6324L73.7503 79.6633ZM74.3542 80.1997C74.3846 80.1476 74.3999 80.1215 74.3999 80.1215L74.3755 80.0287L74.3379 80.1377L74.3542 80.1997ZM73.7783 79.3913L73.793 79.3213C73.7767 79.2594 73.7735 79.2051 73.7833 79.1584L73.8143 79.1503L73.8224 79.1813C73.817 79.1606 73.8143 79.1503 73.8143 79.1503C73.8349 79.1449 73.8452 79.1422 73.8452 79.1422L73.7575 78.9336L73.7493 78.9027C73.7287 78.9081 73.7211 78.9211 73.7265 78.9417C73.7177 79.0764 73.7241 79.185 73.7458 79.2675C73.7306 79.2936 73.7311 79.3375 73.7473 79.3994C73.7473 79.3994 73.7527 79.4201 73.7635 79.4613L73.7783 79.3913ZM73.4596 78.6809C73.4542 78.6603 73.4412 78.6527 73.4205 78.6581L73.4286 78.689C73.4134 78.7151 73.4166 78.7694 73.4383 78.8519C73.4285 78.8986 73.4317 78.9529 73.4479 79.0148L73.4596 78.6809ZM74.3517 79.3071C74.3669 79.281 74.3664 79.2371 74.3501 79.1752L74.3811 79.167C74.3594 79.0845 74.3329 79.0253 74.3014 78.9894L74.2933 78.9585L74.3014 78.9894L74.3207 79.3152L74.3517 79.3071ZM73.7788 78.7626C73.7984 78.6693 73.8001 78.5916 73.7838 78.5297C73.7882 78.4624 73.785 78.4081 73.7742 78.3668L73.7498 78.274L73.7417 78.243C73.7211 78.2484 73.7135 78.2615 73.7189 78.2821L73.727 78.313C73.6813 78.3912 73.6769 78.4585 73.7138 78.515L73.7072 78.616C73.6768 78.6681 73.6697 78.7251 73.6859 78.787L73.7331 78.8408L73.7788 78.7626ZM73.1851 77.7605C73.2003 77.7344 73.2052 77.7111 73.1998 77.6904C73.189 77.6492 73.1912 77.6155 73.2064 77.5895L73.1902 77.5275L73.1754 77.5976L73.1607 77.6676L73.1851 77.7605L73.1932 77.7914L73.1851 77.7605ZM73.7712 78.103L73.763 78.072C73.7468 78.0101 73.7436 77.9558 73.7534 77.9091L73.7143 77.8863L73.7224 77.9173L73.693 78.0573C73.6572 78.0888 73.6523 78.1121 73.6783 78.1273C73.7043 78.1426 73.7201 78.1605 73.7255 78.1811L73.7564 78.173L73.7712 78.103ZM73.7356 77.7153L73.7504 77.6453C73.7287 77.5627 73.7223 77.4541 73.7311 77.3195L73.723 77.2886L73.7148 77.2576L73.6839 77.2657L73.7047 77.7234L73.7438 77.7463L73.7356 77.7153ZM73.1465 77.1089C73.1672 77.1035 73.1748 77.0905 73.1694 77.0699L73.176 76.9689L73.1435 76.8451L73.1272 76.7832L73.1125 76.8532C73.1396 76.9564 73.1482 77.0313 73.1384 77.078L73.1465 77.1089ZM67.6709 72.7557C67.7122 72.7449 67.7301 72.7291 67.7247 72.7085C67.7399 72.6825 67.7448 72.6591 67.7394 72.6385C67.7807 72.6277 67.8089 72.6092 67.8242 72.5832C67.8394 72.5571 67.8443 72.5338 67.8389 72.5131C67.8487 72.4665 67.8791 72.4144 67.9302 72.3569C67.9813 72.2994 68.0117 72.2473 68.0215 72.2006C68.052 72.1485 68.0591 72.0915 68.0429 72.0296C68.0581 72.0035 68.0603 71.9699 68.0495 71.9286L68.0804 71.9205C68.0858 71.9411 68.0912 71.9617 68.0966 71.9824C68.1173 71.977 68.1249 71.9639 68.1195 71.9433C68.1553 71.9119 68.1652 71.8652 68.1489 71.8033C68.1533 71.7359 68.1631 71.6893 68.1783 71.6632C68.1783 71.6632 68.1756 71.6529 68.1702 71.6323C68.1648 71.6116 68.1518 71.604 68.1312 71.6094C68.1105 71.6148 68.0926 71.6306 68.0774 71.6566C68.0828 71.6773 68.0698 71.6696 68.0383 71.6338L68.0545 71.6957C68.0599 71.7163 68.0528 71.7733 68.0332 71.8667C67.9974 71.8981 67.9745 71.9372 67.9647 71.9839C67.9549 72.0306 67.9424 72.067 67.9272 72.093C67.9065 72.0984 67.9016 72.1218 67.9125 72.163C67.9331 72.1576 67.9407 72.1446 67.9353 72.124L67.9744 72.1468C67.9852 72.1881 67.97 72.2141 67.9287 72.2249C67.882 72.2151 67.8434 72.2363 67.813 72.2884C67.7673 72.3665 67.7445 72.4056 67.7445 72.4056C67.776 72.4414 67.7868 72.4827 67.777 72.5294C67.7672 72.5761 67.7546 72.6124 67.7394 72.6385C67.7286 72.5972 67.7102 72.569 67.6841 72.5537L67.64 72.7638L67.6709 72.7557ZM73.383 76.7492C73.3776 76.7285 73.3749 76.7182 73.3749 76.7182C73.3955 76.7128 73.4058 76.7101 73.4058 76.7101C73.3842 76.6275 73.3777 76.519 73.3865 76.3843L73.3703 76.3224L73.315 76.2377L73.3084 76.3387C73.3138 76.3593 73.3116 76.3929 73.3018 76.4396C73.3072 76.4603 73.3256 76.4885 73.3571 76.5244L73.3749 76.7182L73.383 76.7492ZM73.7199 77.0247L73.6991 76.567L73.691 76.536L73.6748 76.4741L73.66 76.5442L73.6697 76.707L73.689 77.0328L73.6971 77.0638L73.7199 77.0247ZM68.2778 71.5379C68.267 71.4966 68.2692 71.4629 68.2844 71.4369L68.2682 71.375L68.2453 71.4141C68.2149 71.4662 68.2051 71.5128 68.2159 71.5541L68.2403 71.647L68.2778 71.5379ZM73.6489 76.2493C73.6435 76.2287 73.6408 76.2184 73.6408 76.2184C73.656 76.1923 73.6609 76.169 73.6555 76.1484C73.6643 76.0137 73.6606 75.9155 73.6443 75.8536C73.6531 75.7189 73.6494 75.6206 73.6332 75.5587L73.625 75.5278C73.625 75.5278 73.6277 75.5381 73.6332 75.5587C73.6332 75.5587 73.6228 75.5614 73.6022 75.5669L73.6184 75.6288L73.6068 75.9627L73.6149 75.9936L73.6068 75.9627L73.6134 75.8617L73.5662 75.8079L73.5743 75.8388C73.5645 75.8855 73.5677 75.9398 73.5839 76.0017C73.5948 76.043 73.5849 76.0897 73.5545 76.1418L73.5789 76.2346C73.5843 76.2553 73.6076 76.2602 73.6489 76.2493ZM68.3905 71.2106C68.4676 71.1683 68.5007 71.1265 68.4899 71.0853L68.4818 71.0543C68.4764 71.0337 68.4634 71.0261 68.4427 71.0315C68.3818 71.1357 68.3514 71.1878 68.3514 71.1878L68.3595 71.2187L68.3905 71.2106ZM73.1364 75.5567L73.1349 75.4248L73.0927 75.1381L73.0846 75.1071L73.0618 75.1462L73.1054 75.5648L73.1135 75.5958L73.1364 75.5567ZM73.0324 75.2862C73.0303 75.1103 73.0185 74.9811 72.9968 74.8986L72.9887 74.8676L72.9968 74.8986L72.9836 75.1005L72.9933 75.2634L73.0014 75.2944L73.0324 75.2862ZM68.29 70.5753L68.2819 70.5443C68.2156 70.6279 68.1775 70.693 68.1677 70.7397L68.1758 70.7707L68.29 70.5753ZM68.6056 71.0218L68.5894 70.9599L68.6188 70.8199C68.6188 70.8199 68.6134 70.7992 68.6026 70.758L68.5503 70.9371L68.5665 70.999L68.5518 71.069L68.6056 71.0218ZM73.0831 74.9752L73.1059 74.9361L73.0897 74.8742L73.0735 74.8123C73.0789 74.833 73.0713 74.846 73.0506 74.8514L73.0522 74.9833L73.0993 75.0371L73.0831 74.9752ZM72.9253 74.7519L72.9091 74.69L72.8928 74.6281C72.8874 74.6075 72.8847 74.5972 72.8847 74.5972C72.9053 74.5918 72.9157 74.589 72.9157 74.589L72.8766 74.5662C72.8766 74.5662 72.8793 74.5765 72.8847 74.5972C72.8847 74.5972 72.8744 74.5999 72.8538 74.6053L72.8781 74.6981L72.8943 74.76L72.9253 74.7519ZM73.2475 75.0975C73.2313 75.0356 73.2281 74.9813 73.2379 74.9346L73.2607 74.8955L73.2917 74.8874L73.2835 74.8565L73.2445 74.8336L73.2054 74.8108L73.2135 74.8417L73.2084 75.0747L73.2166 75.1056L73.2247 75.1366L73.2475 75.0975ZM68.3357 70.4971L68.396 70.349L68.3879 70.318L68.357 70.3261L68.2966 70.4743L68.3047 70.5053L68.3357 70.4971ZM68.7117 70.7955C68.7062 70.7749 68.7188 70.7385 68.7492 70.6864L68.7248 70.5936C68.6792 70.6717 68.6563 70.7108 68.6563 70.7108C68.6672 70.752 68.6856 70.7803 68.7117 70.7955ZM68.632 70.6179C68.6374 70.6386 68.6401 70.6489 68.6401 70.6489C68.6607 70.6435 68.6684 70.6304 68.6629 70.6098L68.7624 70.4845L68.7233 70.4616C68.7179 70.441 68.7076 70.4437 68.6924 70.4697L68.6239 70.587L68.632 70.6179ZM70.6698 72.333C70.685 72.307 70.7133 72.2885 70.7545 72.2777L70.8164 72.2615L70.8702 72.2143L70.8083 72.2305L70.7464 72.2468C70.6845 72.263 70.659 72.2918 70.6698 72.333C70.6231 72.3232 70.5585 72.3291 70.476 72.3508L70.4141 72.367L70.4841 72.3817L70.6698 72.333ZM73.2739 74.6936C73.2945 74.6882 73.3021 74.6751 73.2967 74.6545L73.2886 74.6236L73.2805 74.5926L73.2333 74.5388C73.2333 74.5388 73.2257 74.5518 73.2105 74.5779C73.2105 74.5779 73.2029 74.5909 73.1876 74.617L73.1958 74.6479L73.2267 74.6398L73.2495 74.6007L73.2577 74.6317L73.2658 74.6626L73.2739 74.6936ZM73.5718 74.9463C73.5924 74.9409 73.6027 74.9382 73.6027 74.9382C73.5973 74.9175 73.5946 74.9072 73.5946 74.9072C73.6044 74.8605 73.6012 74.8062 73.5849 74.7443L73.5768 74.7134L73.554 74.7524L73.5555 74.8844L73.5718 74.9463ZM68.7933 70.4763C68.8238 70.4243 68.8363 70.3879 68.8309 70.3672L68.7984 70.2434C68.768 70.2955 68.7555 70.3319 68.7609 70.3525L68.7933 70.4763ZM68.9532 70.2028C68.9532 70.2028 68.976 70.1638 69.0217 70.0856C68.949 70.0606 68.9099 70.0378 68.9045 70.0171C68.874 70.0692 68.8588 70.0953 68.8588 70.0953C68.8436 70.1213 68.8387 70.1447 68.8441 70.1653C68.8495 70.1859 68.8652 70.2039 68.8913 70.2191L68.9385 70.2729L68.9532 70.2028ZM73.5525 74.6205C73.5471 74.5999 73.5547 74.5869 73.5753 74.5814C73.5959 74.576 73.6036 74.563 73.5981 74.5424L73.5951 74.2785L73.5464 74.0928L73.5073 74.07L73.5154 74.1009C73.5425 74.2041 73.5511 74.279 73.5413 74.3257L73.5494 74.3566C73.5657 74.4186 73.5613 74.4859 73.5362 74.5586L73.5525 74.6205ZM73.2191 73.9801C73.2137 73.9595 73.2007 73.9519 73.18 73.9573L73.1262 74.0045L73.1734 74.0583L73.2191 73.9801ZM69.0445 70.0466C69.075 69.9945 69.0902 69.9684 69.0902 69.9684L69.0511 69.9456C69.0099 69.9564 68.9919 69.9721 68.9973 69.9928L69.0445 70.0466ZM68.766 70.1196L68.8411 69.9014L69.0237 69.5889L69.0156 69.5579L68.9847 69.566L68.8411 69.9014L68.735 70.1277L68.7431 70.1587L68.766 70.1196ZM69.1049 69.8984C69.1354 69.8463 69.1506 69.8202 69.1506 69.8202C69.1864 69.7888 69.2115 69.7161 69.2257 69.6021L69.2779 69.4229L69.3302 69.2438C69.3508 69.2384 69.3585 69.2254 69.353 69.2047L69.3221 69.2129C69.3069 69.2389 69.2813 69.2677 69.2455 69.2991C69.2096 69.3306 69.2101 69.3746 69.247 69.4311C69.2165 69.4831 69.191 69.5119 69.1704 69.5173C69.1497 69.5227 69.1318 69.5385 69.1166 69.5645C69.1014 69.5906 69.0965 69.6139 69.1019 69.6345C69.1235 69.7171 69.1137 69.7638 69.0724 69.7746C69.0572 69.8006 69.055 69.8343 69.0658 69.8756L69.1049 69.8984ZM69.0095 69.0302L69.0552 68.952C69.0346 68.9575 69.0215 68.9498 69.0161 68.9292L68.9557 69.0774L68.9639 69.1083L69.0095 69.0302ZM69.2277 69.1053L69.3109 68.918L69.3028 68.8871L69.2719 68.8952L69.2277 69.1053C69.1864 69.1161 69.1506 69.1476 69.1201 69.1997C69.0897 69.2518 69.0799 69.2984 69.0907 69.3397L69.1217 69.3316L69.2277 69.1053ZM69.4525 69.0794L69.4966 68.8693L69.4885 68.8384L69.4576 68.8465L69.3744 69.0337L69.4068 69.1575L69.4525 69.0794ZM70.5353 71.442C70.556 71.4366 70.569 71.4442 70.5744 71.4648C70.595 71.4594 70.613 71.4437 70.6282 71.4176L71.3158 71.138L71.9967 70.9594C72.0478 70.9019 72.0706 70.8628 72.0652 70.8422L72.0409 70.7494L71.9079 69.9902L71.8252 69.5488C71.8296 69.4815 71.821 69.4065 71.7993 69.324L71.7669 69.2002C71.7364 69.2523 71.7212 69.2783 71.7212 69.2783L71.7293 69.3093L71.2594 70.2927C71.1985 70.3969 71.1502 70.4647 71.1143 70.4961C71.0578 70.533 70.9991 70.6036 70.9382 70.7077L70.8484 70.996C70.8288 71.0893 70.8038 71.1621 70.7733 71.2142C70.706 71.2098 70.6571 71.2336 70.6267 71.2857C70.6115 71.3117 70.5859 71.3405 70.5501 71.372C70.5609 71.4132 70.556 71.4366 70.5353 71.442ZM69.6874 68.5877C69.7081 68.5823 69.7184 68.5796 69.7184 68.5796C69.713 68.559 69.7103 68.5486 69.7103 68.5486C69.7407 68.4965 69.7532 68.4602 69.7478 68.4395C69.7783 68.3874 69.8033 68.3147 69.8229 68.2214L69.8067 68.1594L69.7905 68.0975L69.7757 68.1676L69.761 68.2376C69.7458 68.2636 69.7333 68.3 69.7235 68.3467C69.7289 68.3673 69.711 68.3831 69.6697 68.3939L69.6778 68.4248C69.6886 68.4661 69.6864 68.4998 69.6712 68.5258L69.6793 68.5568L69.6874 68.5877ZM72.5133 70.6585C72.5491 70.6271 72.5644 70.601 72.559 70.5804L72.5184 70.4256L72.5331 70.3556C72.5179 70.3816 72.4896 70.4001 72.4483 70.4109L72.4499 70.5428L72.4661 70.6047L72.5133 70.6585ZM72.3651 70.5981L72.3671 70.1014C72.3617 70.0807 72.3487 70.0731 72.3281 70.0785L72.3362 70.1095L72.3392 70.3734C72.3609 70.4559 72.3695 70.5308 72.3651 70.5981L72.3732 70.6291L72.3651 70.5981ZM69.8833 68.0732L69.9437 67.925L69.8965 67.8712L69.8656 67.8793C69.871 67.9 69.8639 67.957 69.8442 68.0503L69.8605 68.1123L69.8833 68.0732ZM72.629 70.5951C72.6496 70.5897 72.6545 70.5663 72.6437 70.5251C72.6427 70.4371 72.6259 70.3312 72.5935 70.2074L72.5772 70.1455L72.5544 70.1846L72.629 70.5951L72.6533 70.688L72.629 70.5951ZM72.494 70.3328L72.5234 70.1927L72.4762 70.1389L72.4615 70.2089C72.4257 70.2404 72.4132 70.2768 72.424 70.318L72.4321 70.349L72.494 70.3328ZM72.901 70.623C72.9422 70.6122 72.9602 70.5965 72.9547 70.5758C72.9754 70.5704 72.9727 70.5601 72.9466 70.5449C72.9412 70.5242 72.9385 70.5139 72.9385 70.5139C72.8918 70.5041 72.8783 70.4525 72.8979 70.3591C72.8925 70.3385 72.9028 70.3358 72.9289 70.351L72.9598 70.3429C72.9544 70.3223 72.9414 70.3147 72.9207 70.3201C72.8632 70.269 72.8497 70.2174 72.8802 70.1653L72.8639 70.1034L72.8248 70.0806L72.833 70.1115C72.8177 70.1376 72.8155 70.1712 72.8264 70.2125C72.8318 70.2331 72.8269 70.2565 72.8117 70.2825L72.8847 70.5611L72.901 70.623ZM72.8497 69.5447C72.8389 69.5035 72.8335 69.4828 72.8335 69.4828C72.8281 69.4622 72.8047 69.4573 72.7635 69.4681C72.758 69.4475 72.7477 69.4502 72.7325 69.4762L72.8025 69.4909L72.8497 69.5447L72.866 69.6066L72.8497 69.5447ZM73.6098 70.1724L73.6083 70.0405L73.5921 69.9786C73.5616 70.0307 73.5464 70.0567 73.5464 70.0567C73.5518 70.0774 73.5469 70.1007 73.5317 70.1268C73.5371 70.1474 73.5528 70.1653 73.5789 70.1805C73.5897 70.2218 73.6054 70.2397 73.6261 70.2343L73.6098 70.1724ZM72.355 69.0459C72.3702 69.0199 72.3675 69.0096 72.3469 69.015L72.3276 68.6892C72.3276 68.6892 72.3173 68.6919 72.2966 68.6973C72.2966 68.6973 72.2939 68.687 72.2885 68.6664L72.2966 68.6973C72.2922 68.7646 72.3063 68.8602 72.3387 68.984L72.355 69.0459ZM73.2617 69.6021L73.2765 69.532C73.271 69.5114 73.258 69.5038 73.2374 69.5092C73.232 69.4886 73.2266 69.4679 73.2211 69.4473L73.2374 69.5092C73.2222 69.5353 73.22 69.5689 73.2308 69.6102L73.278 69.664L73.2617 69.6021ZM74.7784 69.2043C74.773 69.1836 74.7703 69.1733 74.7703 69.1733C74.791 69.1679 74.8013 69.1652 74.8013 69.1652C74.8307 69.0251 74.84 68.9345 74.8292 68.8932L74.6749 68.3051L74.6668 68.2741L74.6749 68.3051L74.7688 69.0414L74.7703 69.1733L74.7784 69.2043ZM77.654 70.2034C77.7257 70.1405 77.7822 70.1036 77.8235 70.0928C77.8387 70.0667 77.849 70.064 77.8544 70.0847C77.8751 70.0792 77.8957 70.0738 77.9164 70.0684L77.9864 70.0831L77.9245 70.0994C77.8419 70.121 77.7827 70.1476 77.7469 70.179L77.654 70.2034ZM82.3831 78.7223C82.4037 78.7169 82.4113 78.7039 82.4059 78.6832L82.4597 78.6361L82.5592 78.5107L82.6896 78.3773C82.7102 78.3719 82.7357 78.3431 82.7662 78.291L82.8966 78.1576L82.9194 78.1185L82.8575 78.1347L82.7662 78.291L82.6505 78.3544L82.6048 78.4326L82.5739 78.4407C82.512 78.4569 82.4864 78.4857 82.4972 78.527C82.5027 78.5476 82.495 78.5606 82.4744 78.566L82.3115 78.5757C82.2703 78.5865 82.2626 78.5995 82.2887 78.6147L82.2821 78.7157L82.2349 78.6619L82.173 78.6782L82.0654 78.7726C82.0654 78.7726 82.0551 78.7753 82.0345 78.7807C82.0192 78.8067 81.9959 78.8018 81.9644 78.766C81.9644 78.766 81.9438 78.7714 81.9025 78.7822C81.8819 78.7876 81.864 78.8033 81.8488 78.8294C81.8444 78.8967 81.8031 78.9075 81.7249 78.8619L81.5392 78.9106L81.5083 78.9187L81.5002 78.8877L81.492 78.8568L81.4611 78.8649L81.4073 78.9121L81.3845 78.9512C81.3845 78.9512 81.3584 78.9359 81.3063 78.9055L81.3291 78.8664L81.3829 78.8192L81.3977 78.7492L81.3357 78.7654C81.3151 78.7709 81.2842 78.779 81.2429 78.7898C81.2223 78.7952 81.2146 78.8082 81.2201 78.8289C81.2255 78.8495 81.2179 78.8625 81.1972 78.8679L81.1891 78.837L81.1028 78.7604C81.1028 78.7604 81.0876 78.7864 81.0572 78.8385C81.068 78.8798 81.0631 78.9031 81.0425 78.9085C80.9599 78.9302 80.9132 78.9204 80.9024 78.8791C80.8655 78.8226 80.8265 78.7998 80.7852 78.8106C80.7646 78.816 80.7515 78.8084 80.7461 78.7878L80.7136 78.664C80.7235 78.6173 80.705 78.589 80.6583 78.5792C80.6323 78.564 80.6089 78.5591 80.5883 78.5645C80.547 78.5753 80.4976 78.5552 80.4401 78.5041C80.3207 78.4693 80.2328 78.4703 80.1763 78.5072L80.1144 78.5234L80.1291 78.4534C80.1595 78.4013 80.1411 78.373 80.0738 78.3686L79.9419 78.3702C79.8539 78.3712 79.8077 78.4053 79.8033 78.4727C79.8033 78.4727 79.7881 78.4987 79.7577 78.5508L79.7105 78.497C79.6942 78.4351 79.6964 78.4014 79.7171 78.396C79.7627 78.3179 79.7666 78.2066 79.7287 78.0621L79.6998 77.5735C79.7194 77.4801 79.7238 77.4128 79.713 77.3715C79.7228 77.3249 79.7196 77.2706 79.7034 77.2087L79.7181 77.1386L79.7232 76.9057L79.7379 76.8357L79.7429 76.6028L79.712 76.6109L79.6826 76.751L79.6501 76.6271L79.6552 76.3942L79.5791 75.8518C79.5574 75.7693 79.5662 75.6346 79.6054 75.4479C79.6153 75.4012 79.6224 75.3442 79.6268 75.2769C79.6257 75.1889 79.6198 75.1243 79.609 75.0831L79.6273 74.6482L79.8089 73.575L79.9267 73.0148L80.0495 72.2217L80.293 71.1322L80.3372 70.9222C80.3568 70.8288 80.3482 70.7539 80.3113 70.6974C80.243 70.605 80.1611 70.4611 80.0657 70.2656C80.0224 70.1005 80.0133 69.9816 80.0383 69.9088C80.0427 69.8415 80.0471 69.7742 80.0515 69.7069C80.0505 69.6189 80.0598 69.5283 80.0794 69.4349L80.1088 69.2949C80.1849 69.1646 80.2198 69.0452 80.2134 68.9366C80.2536 68.8378 80.3401 68.7049 80.4727 68.5378C80.5444 68.4749 80.6465 68.3598 80.7791 68.1927C80.84 68.0885 80.9243 67.9893 81.0318 67.8949C81.0525 67.8895 81.078 67.8607 81.1085 67.8086L81.4368 66.6639L81.5921 65.9946C81.6726 65.797 81.7096 65.6439 81.7032 65.5353C81.7174 65.4213 81.7343 65.3177 81.7539 65.2243C81.7888 65.1049 81.8187 65.0088 81.8437 64.9361L82.0528 64.2196C82.0768 64.0589 82.1215 63.8928 82.1868 63.7213C82.2652 63.3478 82.3111 63.0601 82.3243 62.8582C82.3331 62.7235 82.3527 62.6302 82.3831 62.5781L82.4111 62.3061L82.5075 61.9169C82.5021 61.8963 82.5097 61.8832 82.5303 61.8778C82.489 61.8887 82.4684 61.8941 82.4684 61.8941C82.1599 62.0632 81.9339 62.2107 81.7905 62.3365C81.7546 62.368 81.7318 62.4071 81.722 62.4538C81.7274 62.4744 81.7355 62.5053 81.7463 62.5466L81.7316 62.6166C81.6805 62.6741 81.6262 62.6774 81.5687 62.6263C81.5373 62.5904 81.5058 62.5546 81.4743 62.5187C81.4375 62.4622 81.38 62.4111 81.3018 62.3655C81.2758 62.3502 81.26 62.3323 81.2546 62.3117C81.2699 62.2856 81.2748 62.2623 81.2693 62.2416C81.2531 62.1797 81.2271 62.1645 81.1912 62.196L81.0298 62.3375C81.0353 62.3582 81.0276 62.3712 81.007 62.3766C81.007 62.3766 81.0043 62.3663 80.9989 62.3457L80.9679 62.3538L80.9761 62.3847L80.9923 62.4466L80.9532 62.4238C80.9272 62.4086 80.8935 62.4064 80.8522 62.4172C80.8316 62.4226 80.7854 62.4568 80.7137 62.5197C80.6724 62.5305 80.6779 62.5512 80.7299 62.5816L80.7462 62.6435L80.7152 62.6516C80.6425 62.6266 80.5627 62.6586 80.4757 62.7475C80.404 62.8105 80.347 62.8034 80.3047 62.7262C80.2679 62.6697 80.2288 62.6469 80.1875 62.6577C80.13 62.6066 80.1089 62.5681 80.1241 62.542C80.1078 62.4801 80.0737 62.434 80.0216 62.4035C79.9847 62.347 79.9869 62.3134 80.0282 62.3025C80.0282 62.3025 80.0434 62.2765 80.0738 62.2244C80.0326 62.2352 79.9989 62.233 79.9729 62.2178L79.9419 62.2259C79.88 62.2421 79.8643 62.2242 79.8947 62.1721L79.8785 62.1102L79.916 62.0011L79.9079 61.9702L79.877 61.9783C79.8617 62.0043 79.8411 62.0097 79.8151 61.9945C79.8097 61.9739 79.8146 61.9505 79.8298 61.9245L79.8364 61.8235L79.8658 61.6835L79.8805 61.6134L80.2098 61.2293C80.4652 60.9418 80.8113 60.6636 81.248 60.3946C81.6848 60.1257 81.952 59.9674 82.0498 59.9197C82.1421 59.8513 82.3067 59.7641 82.5435 59.6578C82.6359 59.5895 82.8004 59.5022 83.0372 59.396C83.4902 59.189 83.8068 59.0508 83.9871 58.9814L84.6128 58.7181C84.7779 58.6748 84.8859 58.6244 84.937 58.5669C85.0196 58.5452 85.0842 58.5393 85.1309 58.5491C85.2753 58.5112 85.3731 58.4635 85.4242 58.406C85.4394 58.38 85.4986 58.3534 85.6018 58.3264L85.9585 58.299L86.1214 58.2893C86.2093 58.2883 86.2555 58.2541 86.2599 58.1868L86.3137 58.1396C86.407 58.1593 86.4847 58.161 86.5466 58.1447L86.5938 58.1985L86.5628 58.2066L86.3852 58.2863C86.3646 58.2917 86.3336 58.2998 86.2924 58.3106C86.2663 58.2954 86.2484 58.3111 86.2386 58.3578C86.244 58.3785 86.2157 58.3969 86.1538 58.4131C86.0094 58.451 85.9089 58.4884 85.8524 58.5253L85.7905 58.5415L85.8605 58.5562C86.005 58.5183 86.1625 58.4881 86.333 58.4654C86.5187 58.4167 86.6707 58.3658 86.7891 58.3127C86.8923 58.2856 87.0319 58.2711 87.2078 58.269L87.7126 58.302C87.7072 58.2814 87.7148 58.2684 87.7355 58.263L87.7893 58.2158L87.9603 58.2371C88.0384 58.2827 88.0694 58.2746 88.0531 58.2127L88.0841 58.2046C88.1666 58.1829 88.2312 58.177 88.2779 58.1868L88.76 58.2589C88.7806 58.2535 88.8376 58.2606 88.931 58.2802C89.1167 58.2315 89.298 58.2501 89.4749 58.336C89.527 58.3665 89.5998 58.3915 89.6931 58.4111C89.8125 58.446 89.9118 58.5302 89.991 58.6638C90.0387 58.7616 90.1309 58.9028 90.2675 59.0875C90.3673 59.2157 90.4389 59.3624 90.4822 59.5275C90.5092 59.6306 90.5184 59.7495 90.5096 59.8842C90.5008 60.0188 90.4942 60.1198 90.4898 60.1871C90.4614 60.4151 90.4297 60.5888 90.3949 60.7082L90.2838 61.1675L90.1549 61.4328L89.9737 61.8774C89.6463 62.6469 89.495 62.9954 89.5201 62.9226L89.3521 63.1652C89.3521 63.1652 89.3217 63.2173 89.2608 63.3215C89.1847 63.4517 89.1466 63.5168 89.1466 63.5168L89.1319 63.5869L89.1628 63.5787L89.14 63.6178L88.9573 63.9304L88.5773 64.6256L88.1647 65.1969L87.9054 65.5958C87.9054 65.5958 87.8522 65.6869 87.7456 65.8693C87.6847 65.9734 87.6363 66.0413 87.6005 66.0727C87.5646 66.1042 87.5315 66.146 87.501 66.1981C87.4912 66.2448 87.4581 66.2865 87.4016 66.3234C87.3863 66.3494 87.3249 66.4097 87.2174 66.504C87.0892 66.6038 87.013 66.7341 86.989 66.8948C86.9738 66.9208 86.9227 66.9783 86.8358 67.0673L86.7901 67.1454C86.7955 67.1661 86.8189 67.171 86.8601 67.1601C86.9481 67.1591 87.0979 67.1419 87.3097 67.1084C87.5215 67.0749 87.7001 67.0832 87.8456 67.1333L88.2591 67.3225L88.5164 67.4205C88.6358 67.4553 88.7894 67.5363 88.9771 67.6635L89.3759 67.9228C89.517 68.0402 89.5984 68.1402 89.62 68.2227C89.6254 68.2433 89.6439 68.2716 89.6753 68.3074C89.7068 68.3433 89.7149 68.3743 89.6997 68.4003C89.7051 68.4209 89.6975 68.434 89.6768 68.4394L89.685 68.4703C89.7164 68.5062 89.7403 68.5551 89.7565 68.617C89.7673 68.6582 89.7885 68.6968 89.8199 68.7327C89.846 68.7479 89.8541 68.7788 89.8443 68.8255C89.8497 68.8462 89.8551 68.8668 89.8605 68.8874C89.8714 68.9287 89.8773 68.9933 89.8783 69.0813C89.8739 69.1486 89.8901 69.2105 89.927 69.267L89.9351 69.2979C89.8895 69.3761 89.9084 69.4483 89.992 69.5146L89.961 69.5227C89.8947 69.6063 89.8957 69.6942 89.964 69.7866L90.0031 69.8094C89.9825 69.8148 89.9651 69.8745 89.9509 69.9885C89.9563 70.0092 89.9514 70.0325 89.9361 70.0586C89.9209 70.0846 89.9187 70.1183 89.9295 70.1595C89.9089 70.165 89.9013 70.178 89.9067 70.1986C89.9273 70.1932 89.9377 70.1905 89.9377 70.1905C89.9583 70.1851 89.9713 70.1927 89.9767 70.2133C89.9821 70.234 89.9979 70.2519 90.0239 70.2671L89.962 70.2834L89.9311 70.2915C89.9571 70.3067 89.9522 70.33 89.9163 70.3615C89.8957 70.3669 89.8881 70.3799 89.8935 70.4006C89.9196 70.4158 89.9353 70.4337 89.9407 70.4544C89.9461 70.475 89.9618 70.4929 89.9879 70.5081L90.0188 70.5C90.0733 70.2873 90.0951 70.1602 90.0843 70.119C90.1039 70.0256 90.1132 69.9349 90.1122 69.847C90.1112 69.759 90.1053 69.6944 90.0945 69.6531L90.0818 69.2264L90.0249 69.0097L89.859 68.7555L89.8428 68.6936C89.8634 68.6882 89.8764 68.6958 89.8818 68.7164L90.0234 68.8778C90.0397 68.9397 90.0814 68.9729 90.1488 68.9772C90.1694 68.9718 90.1851 68.9898 90.1959 69.031C90.2014 69.0517 90.2171 69.0696 90.2431 69.0848L90.2822 69.1077C90.3387 69.0708 90.3778 69.0936 90.3994 69.1762C90.4102 69.2174 90.4211 69.2587 90.4319 69.3C90.4634 69.3358 90.4769 69.3874 90.4725 69.4547L90.542 70.0982C90.5593 70.248 90.5439 70.4836 90.4958 70.805C90.4326 71.1524 90.2639 71.5606 89.9899 72.0294C89.792 72.368 89.5273 72.7462 89.1958 73.164L88.798 73.6653C88.7317 73.7489 88.6268 73.8536 88.4834 73.9794C88.4269 74.0163 88.3682 74.0868 88.3073 74.191L88.0155 74.4661L87.6862 74.8502L86.7343 75.7615C86.6984 75.793 86.6446 75.8402 86.5729 75.9031C86.5218 75.9606 86.4604 76.0208 86.3887 76.0837L85.9356 76.5003L85.5509 76.7997L85.3667 76.9803L85.3358 76.9885C85.3662 76.9364 85.4249 76.8658 85.5119 76.7769L85.8036 76.5018C85.8243 76.4964 85.8319 76.4834 85.8265 76.4628C85.8982 76.3998 85.9569 76.3293 86.0025 76.2512C86.0743 76.1883 86.146 76.1253 86.2177 76.0624C86.31 75.9941 86.3818 75.9312 86.4328 75.8737C86.4992 75.7901 86.5578 75.7196 86.6089 75.6621L86.7622 75.4895L86.785 75.4505L86.754 75.4586L86.5308 75.6164C86.4851 75.6945 86.3906 75.7965 86.2471 75.9224L85.8168 76.2999L85.5169 76.544L85.4941 76.583C85.4582 76.6145 85.4224 76.6459 85.3865 76.6774C85.3507 76.7089 85.3175 76.7506 85.2871 76.8027L85.2561 76.8109C85.2094 76.8011 85.1682 76.8119 85.1323 76.8433C85.1019 76.8954 85.066 76.9269 85.0247 76.9377C85.0095 76.9638 84.9813 76.9822 84.94 76.993C84.9194 76.9984 84.9014 77.0142 84.8862 77.0402L84.8634 77.0793L84.6711 77.229C84.6711 77.229 84.6504 77.2344 84.6092 77.2452C84.6298 77.2398 84.6374 77.2268 84.632 77.2061L84.7934 77.0646L84.8162 77.0255L84.7462 77.0108C84.6223 77.0433 84.53 77.1116 84.4691 77.2158C84.4539 77.2418 84.4153 77.263 84.3534 77.2792C84.3588 77.2998 84.3485 77.3026 84.3225 77.2873C84.3225 77.2873 84.3148 77.3004 84.2996 77.3264L84.0079 77.6014L83.9703 77.7105C83.9497 77.7159 83.9394 77.7186 83.9394 77.7186C83.9448 77.7393 83.9475 77.7496 83.9475 77.7496L83.8856 77.7658L83.7618 77.7983L83.8221 77.6501L83.9916 77.5395L84.0454 77.4923C84.065 77.399 84.1107 77.3208 84.1824 77.2579C84.2595 77.2156 84.3057 77.1814 84.3209 77.1554L84.6893 76.7941L84.7122 76.755L84.6812 76.7632L84.5802 76.7566C84.6215 76.7457 84.6807 76.7192 84.7578 76.6769C84.835 76.6346 84.8915 76.5977 84.9273 76.5663L85.1115 76.3856C85.1876 76.2554 85.2257 76.1903 85.2257 76.1903L85.3561 76.0568C85.3767 76.0514 85.387 76.0487 85.387 76.0487C85.3816 76.0281 85.3789 76.0178 85.3789 76.0178L85.348 76.0259L85.2404 76.1203C85.1839 76.1571 85.1046 76.2331 85.0024 76.3481L84.5802 76.7566L84.3422 76.9844L83.6283 77.6679L82.9829 78.2342L82.7987 78.4148C82.7324 78.4984 82.6606 78.5613 82.5835 78.6036C82.527 78.6405 82.4808 78.6746 82.445 78.7061L82.3831 78.7223ZM79.9195 77.7805C79.9195 77.7805 79.9168 77.7702 79.9114 77.7496C79.9114 77.7496 79.9217 77.7469 79.9424 77.7415L79.9261 77.6796L79.8708 77.5948L79.8333 77.7039L79.8642 77.6958L79.8805 77.7577C79.8859 77.7783 79.8989 77.7859 79.9195 77.7805ZM80.5188 77.9211L80.5026 77.8592L80.4554 77.8054C80.4662 77.8467 80.4613 77.87 80.4407 77.8754L80.4569 77.9373L80.5041 77.9911L80.5188 77.9211ZM82.7606 79.1526C82.7552 79.132 82.7525 79.1217 82.7525 79.1217C82.7731 79.1163 82.7834 79.1135 82.7834 79.1135L82.8372 79.0664L83.2903 78.6498C83.3208 78.5977 83.3463 78.5689 83.367 78.5635L83.3979 78.5554C83.4294 78.5912 83.4272 78.6249 83.3913 78.6564C83.3761 78.6824 83.3685 78.6954 83.3685 78.6954L82.8991 79.0501L82.7915 79.1445L82.7606 79.1526ZM81.9568 78.1063L81.9487 78.0754L81.8411 78.1697C81.8205 78.1751 81.8129 78.1882 81.8183 78.2088L81.8493 78.2007L81.9568 78.1063ZM82.9027 78.6853C82.9027 78.6853 82.8924 78.688 82.8717 78.6934C82.8717 78.6934 82.869 78.6831 82.8636 78.6624L82.8017 78.6787L82.8555 78.6315C82.8859 78.5794 82.9576 78.5165 83.0706 78.4427C83.0913 78.4373 83.1043 78.4449 83.1097 78.4656L83.1178 78.4965C83.0048 78.5703 82.9331 78.6332 82.9027 78.6853ZM79.9084 77.4857L79.9591 77.1747L79.9479 76.8798L79.9596 76.546L79.9124 76.4922L79.8668 76.5703C79.8678 76.6583 79.8639 76.7696 79.8551 76.9042C79.8463 77.0388 79.8532 77.1914 79.8759 77.3619L79.8693 77.4629L79.8855 77.5248L79.9084 77.4857ZM82.0563 77.981C82.0976 77.9701 82.1155 77.9544 82.1101 77.9338L82.3481 77.7059L82.3937 77.6278C82.3525 77.6386 82.3242 77.6571 82.309 77.6831C82.2884 77.6885 82.2193 77.7618 82.102 77.9028L82.0482 77.95L82.0563 77.981ZM82.2856 78.3509C82.3986 78.2771 82.4654 78.2376 82.4861 78.2321C82.4807 78.2115 82.4986 78.1958 82.5399 78.185C82.5453 78.2056 82.5583 78.2132 82.5789 78.2078L82.8479 77.9718C82.8685 77.9664 82.8864 77.9507 82.9017 77.9246C82.9375 77.8932 82.9397 77.8595 82.9083 77.8237L83.0843 77.6121C83.2843 77.4494 83.3995 77.342 83.4299 77.2899L83.4837 77.2427L83.4527 77.2508C83.4267 77.2356 83.393 77.2334 83.3518 77.2442L83.2066 77.4477C83.161 77.5258 83.1148 77.56 83.0681 77.5502C83.0268 77.561 82.9703 77.5979 82.8986 77.6608C82.8628 77.6922 82.8579 77.7156 82.8839 77.7308L82.8301 77.778C82.8041 77.7628 82.7552 77.7866 82.6835 77.8496C82.6378 77.9277 82.6047 77.9695 82.584 77.9749C82.5427 77.9857 82.5096 78.0275 82.4846 78.1002C82.4172 78.0958 82.3684 78.1197 82.3379 78.1718C82.3075 78.2239 82.2846 78.2629 82.2694 78.289L82.2156 78.3362L82.2856 78.3509ZM83.2193 77.8744C83.2552 77.843 83.291 77.8115 83.3269 77.78C83.3627 77.7486 83.3959 77.7068 83.4263 77.6547L83.4964 77.6694L83.4492 77.6156L83.3873 77.6319L83.2797 77.7262L82.9651 78.0403L82.9113 78.0875L83.0123 78.0941L83.2193 77.8744ZM83.4162 78.1205L83.439 78.0814L83.6851 77.8846L83.7242 77.9074L83.7095 77.9774L83.4862 78.1352L83.4162 78.1205ZM82.5368 77.9211L83.166 77.2929L83.197 77.2848C83.1916 77.2642 83.1786 77.2565 83.1579 77.262L83.1041 77.3091C82.7716 77.639 82.5798 77.8326 82.5287 77.8901L82.4749 77.9373L82.5368 77.9211ZM82.2735 77.2954L82.4577 77.1148L82.4724 77.0448L82.4105 77.061L82.2425 77.3036L82.2735 77.2954ZM83.6496 77.4969L83.6415 77.4659L83.5943 77.4122L83.4558 77.5147L83.472 77.5766L83.503 77.5684L83.5958 77.5441C83.6066 77.5854 83.6273 77.5799 83.6577 77.5278L83.6496 77.4969ZM82.9854 77.1087L82.9773 77.0778L82.9463 77.0859L82.8159 77.2193C82.8213 77.24 82.8343 77.2476 82.855 77.2422L82.9854 77.1087ZM82.7494 76.8398C82.7799 76.7877 82.8157 76.7562 82.857 76.7454L82.8179 76.7226L82.6794 76.8251L82.6875 76.856L82.7494 76.8398ZM83.2736 77.1985L83.435 77.057L83.7039 76.821L83.7267 76.7819L83.6958 76.7901L83.5882 76.8844C83.4394 76.9896 83.3242 77.097 83.2427 77.2066C83.2427 77.2066 83.2323 77.2094 83.2117 77.2148C83.2117 77.2148 83.2144 77.2251 83.2198 77.2457L83.2508 77.2376L83.2736 77.1985ZM82.6992 76.5221C82.7763 76.4798 82.8377 76.4196 82.8834 76.3415L82.9144 76.3334L82.8834 76.3415C82.7758 76.4359 82.7144 76.4961 82.6992 76.5221ZM83.5913 77.1483L84.1748 76.5982C84.1954 76.5928 84.2058 76.5901 84.2058 76.5901C84.2003 76.5695 84.1976 76.5592 84.1976 76.5592L84.1895 76.5282C84.1895 76.5282 84.1792 76.5309 84.1586 76.5363C84.1586 76.5363 84.1613 76.5467 84.1667 76.5673L83.8668 76.8114L83.5831 77.1173L83.5294 77.1645L83.5913 77.1483ZM83.7409 77.3406L84.1631 76.9321C84.1936 76.88 84.2088 76.854 84.2088 76.854L84.2854 76.7677L84.4777 76.618C84.5082 76.5659 84.5234 76.5399 84.5234 76.5399L84.4305 76.5642L84.2007 76.823L84.2088 76.854L84.1159 76.8783L83.9089 77.0981L83.6938 77.2868L83.679 77.3568L83.7409 77.3406ZM83.3411 76.3207L83.6019 76.0538L83.6476 75.9756L83.6166 75.9838L83.5319 76.0391L83.302 76.2978L83.3101 76.3288L83.3411 76.3207ZM84.5122 76.2451L84.5041 76.2141C84.4324 76.277 84.3813 76.3346 84.3509 76.3866L84.3818 76.3785L84.5122 76.2451ZM84.7842 76.273C84.8049 76.2676 84.8152 76.2649 84.8152 76.2649C84.8098 76.2442 84.8071 76.2339 84.8071 76.2339C84.8071 76.2339 84.7967 76.2366 84.7761 76.242C84.7707 76.2214 84.7604 76.2241 84.7451 76.2502L84.6229 76.4146L84.631 76.4455L84.7842 76.273ZM84.8918 76.1786L85.1526 75.9117C85.1732 75.9063 85.1809 75.8933 85.1754 75.8726L85.1673 75.8417C85.1413 75.8265 85.1103 75.8346 85.0745 75.866C85.0538 75.8714 85.0359 75.8872 85.0207 75.9132C85.0315 75.9545 85.0163 75.9805 84.975 75.9914C84.9283 75.9816 84.9001 76 84.8903 76.0467C84.8805 76.0934 84.8679 76.1297 84.8527 76.1558L84.8608 76.1867L84.8918 76.1786ZM86.3983 76.2466L86.5059 76.1522C86.5211 76.1262 86.5287 76.1132 86.5287 76.1132C86.5548 76.1284 86.5781 76.1333 86.5988 76.1279L86.5759 76.1669L86.4065 76.2776L86.3983 76.2466ZM85.42 75.5438C85.4038 75.4819 85.432 75.4635 85.5048 75.4885C85.5254 75.4831 85.533 75.4701 85.5276 75.4494L85.5423 75.3794L85.5032 75.3566C85.4468 75.3935 85.3957 75.451 85.35 75.5291C85.3196 75.5812 85.3097 75.6279 85.3206 75.6692L85.3906 75.6839L85.42 75.5438ZM85.8732 75.1272C85.9036 75.0751 85.9188 75.0491 85.9188 75.0491L85.9807 75.0328L86.0426 75.0166C86.0318 74.9753 86.0161 74.9574 85.9955 74.9628L85.9335 74.9791L85.9188 75.0491C85.8667 75.0186 85.8483 74.9904 85.8635 74.9643L85.8945 74.9562C85.8945 74.9562 85.8842 74.9589 85.8635 74.9643C85.8581 74.9437 85.8581 74.9437 85.8635 74.9643C85.8222 74.9752 85.8043 74.9909 85.8097 75.0115L85.795 75.0816C85.8004 75.1022 85.8162 75.1201 85.8422 75.1353C85.8628 75.1299 85.8732 75.1272 85.8732 75.1272ZM84.9973 74.563L85.074 74.4767L85.043 74.4848C85.0017 74.4956 84.9838 74.5114 84.9892 74.532L84.9126 74.6183L84.9973 74.563ZM85.3576 74.1707L85.3495 74.1398C85.3495 74.1398 85.3392 74.1425 85.3185 74.1479C85.3185 74.1479 85.3213 74.1582 85.3267 74.1788C85.306 74.1843 85.237 74.2575 85.1196 74.3986L85.1278 74.4295L85.3576 74.1707ZM82.7931 73.2223C82.7877 73.2017 82.7953 73.1887 82.8159 73.1833C82.8356 73.0899 82.8449 72.9992 82.8438 72.9113C82.8635 72.8179 82.8907 72.7115 82.9255 72.5921L83.0301 72.2339L83.061 72.2258L83.0382 72.2648L82.9352 72.755C82.8959 72.9417 82.8562 73.0845 82.8159 73.1833C82.8159 73.1833 82.8186 73.1936 82.824 73.2142C82.824 73.2142 82.8137 73.2169 82.7931 73.2223ZM86.103 74.8684C86.1237 74.863 86.1416 74.8473 86.1568 74.8212C86.1927 74.7898 86.2052 74.7534 86.1944 74.7122L86.2253 74.704C86.2612 74.6726 86.3204 74.646 86.4029 74.6244C86.4235 74.619 86.4312 74.6059 86.4257 74.5853C86.4257 74.5853 86.479 74.4941 86.5856 74.3118C86.5802 74.2912 86.5775 74.2808 86.5775 74.2808C86.5981 74.2754 86.6084 74.2727 86.6084 74.2727L86.6165 74.3037L86.6784 74.2874L86.8236 74.084C86.854 74.0319 86.885 74.0237 86.9164 74.0596L86.9474 74.0515L87.024 73.9652C87.0446 73.9598 87.055 73.9571 87.055 73.9571C87.0495 73.9365 87.0468 73.9262 87.0468 73.9262C86.9687 73.8805 86.9709 73.8468 87.0534 73.8252C87.048 73.8045 87.0556 73.7915 87.0763 73.7861L87.0453 73.7942C87.004 73.805 86.9476 73.8419 86.8758 73.9048L86.8221 73.952L86.713 73.9145C86.6673 73.9926 86.6445 74.0317 86.6445 74.0317C86.6292 74.0577 86.5961 74.0995 86.545 74.157L86.514 74.1652L86.2923 74.4549C86.2717 74.4603 86.2668 74.4836 86.2776 74.5249L86.2857 74.5559L86.2547 74.564C86.2081 74.5542 86.1695 74.5753 86.1391 74.6274L86.1243 74.6974C86.1504 74.7127 86.1558 74.7333 86.1406 74.7593C86.1254 74.7854 86.0971 74.8038 86.0558 74.8147C86.045 74.7734 86.032 74.7658 86.0168 74.7918C85.9755 74.8026 85.9603 74.8287 85.9711 74.87C86.0438 74.895 86.0878 74.8945 86.103 74.8684ZM85.488 74.0373C85.5087 74.0319 85.5163 74.0188 85.5109 73.9982L85.6413 73.8648L85.7717 73.7313L85.7945 73.6922L85.7017 73.7166C85.5995 73.8316 85.5256 73.9282 85.4799 74.0063L85.488 74.0373ZM86.068 73.8521C86.068 73.8521 86.0707 73.8624 86.0761 73.883C86.0968 73.8776 86.1044 73.8646 86.099 73.8439L86.2065 73.7496L86.2603 73.7024L86.1984 73.7186L86.068 73.8521ZM86.9748 74.4082L87.4345 73.8906L87.4655 73.8825L87.3954 73.8678C87.4009 73.8884 87.3829 73.9042 87.3417 73.915L87.1965 74.1185L86.9129 74.4244L86.89 74.4635L86.921 74.4554L86.9748 74.4082ZM86.275 73.6324C86.3163 73.6215 86.3446 73.6031 86.3598 73.577C86.3804 73.5716 86.406 73.5429 86.4364 73.4908L86.3745 73.507L86.3207 73.5542C86.2903 73.6063 86.275 73.6324 86.275 73.6324ZM86.9672 73.7486L86.9591 73.7176L86.8972 73.7338L86.8205 73.8201C86.8618 73.8093 86.8824 73.8039 86.8824 73.8039L86.9672 73.7486ZM82.103 76.6454L82.6637 76.1345C82.7659 76.0194 82.9245 75.8675 83.1397 75.6788L83.7607 75.0196C83.8531 74.9513 83.9862 74.8282 84.1601 74.6502C84.2112 74.5927 84.2726 74.5325 84.3443 74.4696C84.4106 74.386 84.4872 74.2998 84.5742 74.2108L85.487 73.2766C85.6304 73.1508 85.8196 72.9468 86.0543 72.6647L86.6201 71.9208C86.7321 71.7591 86.9054 71.5372 87.1402 71.2551C87.3946 70.8796 87.5621 70.593 87.6426 70.3955C87.6872 70.2294 87.7145 70.123 87.7243 70.0763L87.7227 69.9444L87.7329 69.4786L87.7085 69.3857C87.6815 69.2825 87.6159 69.2005 87.5117 69.1396C87.491 69.145 87.4807 69.1477 87.4807 69.1477C87.4753 69.1271 87.4726 69.1168 87.4726 69.1168L87.5035 69.1087C87.5035 69.1087 87.5556 69.1391 87.6598 69.2L87.7836 69.1675C87.7836 69.1675 87.7809 69.1572 87.7755 69.1366C87.7907 69.1105 87.7853 69.0899 87.7593 69.0747C87.743 69.0128 87.7013 68.9796 87.634 68.9752C87.5819 68.9448 87.5401 68.9116 87.5086 68.8758C87.4826 68.8605 87.4462 68.848 87.3995 68.8382C87.3528 68.8284 87.3165 68.8159 87.2904 68.8007C87.285 68.78 87.2747 68.7827 87.2595 68.8088C87.2442 68.8348 87.216 68.8533 87.1747 68.8641C87.128 68.8543 87.0944 68.8521 87.0738 68.8575C87.0531 68.8629 87.0195 68.8607 86.9728 68.8509C86.9261 68.8411 86.8821 68.8416 86.8408 68.8524C86.7735 68.848 86.678 68.862 86.5542 68.8945L85.6484 69.099L85.3389 69.1802C85.1944 69.2181 85.0836 69.2582 85.0065 69.3005C84.9706 69.3319 84.9218 69.3558 84.8599 69.372C84.7925 69.3676 84.7409 69.3811 84.7051 69.4126C84.6225 69.4342 84.5248 69.4819 84.4118 69.5557C84.3912 69.5611 84.3836 69.5741 84.389 69.5948L84.4199 69.5866C84.585 69.5433 84.7115 69.5212 84.7995 69.5202L84.8304 69.5121L84.7995 69.5202L84.599 69.6389L84.5371 69.6551C84.5165 69.6606 84.5089 69.6736 84.5143 69.6942C84.5143 69.6942 84.517 69.7045 84.5224 69.7252C84.5224 69.7252 84.5327 69.7225 84.5534 69.7171L84.7081 69.6765L84.9248 69.6196L84.9639 69.6425L84.9329 69.6506L84.871 69.6668L84.3301 69.8749L84.2682 69.8911C84.2736 69.9117 84.2763 69.922 84.2763 69.922C84.2969 69.9166 84.3073 69.9139 84.3073 69.9139L84.3154 69.9449C84.3208 69.9655 84.3338 69.9731 84.3545 69.9677L85.0664 69.781L85.0745 69.8119L85.2211 69.7404L85.2912 69.7551L85.2374 69.8023L84.6183 69.9647C84.412 70.0188 84.2034 70.1066 83.9927 70.228C83.9622 70.2801 83.9264 70.3116 83.8851 70.3224L83.5608 70.4736C83.3393 70.5538 83.2403 70.7231 83.264 70.9815L83.2198 71.1916C83.2198 71.1916 83.2046 71.2177 83.1742 71.2698C83.1742 71.2698 83.1796 71.2904 83.1904 71.3317C83.2219 71.3675 83.2143 71.3806 83.1676 71.3707L83.1366 71.3789C83.1475 71.4201 83.1431 71.4875 83.1234 71.5808L83.1052 72.0157L83.0905 72.0857L83.0514 72.0629L83.0661 71.9928L83.058 71.9619C83.0472 71.9206 83.0211 71.9054 82.9798 71.9162C82.9852 71.9369 82.9803 71.9602 82.9651 71.9863C82.9445 71.9917 82.9472 72.002 82.9732 72.0172C82.9949 72.0997 82.9981 72.154 82.9829 72.1801C82.9677 72.2061 82.9524 72.2322 82.9372 72.2582C82.922 72.2843 82.9198 72.3179 82.9306 72.3592C82.8413 72.6914 82.7846 72.9378 82.7606 73.0985C82.7258 73.2179 82.7241 73.2956 82.7555 73.3314C82.7555 73.3314 82.7452 73.3341 82.7246 73.3396C82.7246 73.3396 82.7273 73.3499 82.7327 73.3705C82.6576 73.5887 82.6201 73.6978 82.6201 73.6978C82.6004 73.7912 82.5389 74.0609 82.4354 74.5071C82.3068 75.0261 82.2305 75.3659 82.2065 75.5266C82.1727 75.7339 82.1361 75.931 82.0969 76.1177C82.0783 76.299 82.057 76.47 82.033 76.6307L82.0492 76.6926L82.103 76.6454ZM86.6582 73.201L86.6272 73.2092L86.5506 73.2954C86.556 73.3161 86.5587 73.3264 86.5587 73.3264C86.5793 73.321 86.5897 73.3183 86.5897 73.3183L86.6582 73.201ZM86.8961 72.9732L87.2026 72.6282L87.1945 72.5972L87.1636 72.6053C87.1483 72.6314 87.1201 72.6498 87.0788 72.6606C87.0582 72.666 87.0402 72.6818 87.025 72.7078C87.0359 72.7491 87.0282 72.7621 87.0022 72.7469C86.9968 72.7263 86.9838 72.7187 86.9631 72.7241L86.9403 72.7631L86.9875 72.8169L86.9337 72.8641L86.8571 72.9504L86.8652 72.9813L86.8961 72.9732ZM87.2295 73.6136C87.286 73.5767 87.3322 73.5425 87.368 73.5111C87.4245 73.4742 87.4707 73.44 87.5066 73.4086C87.5218 73.3825 87.5397 73.3668 87.5604 73.3614C87.581 73.356 87.5886 73.343 87.5832 73.3223C87.5571 73.3071 87.567 73.2604 87.6126 73.1823C87.6431 73.1302 87.6453 73.0965 87.6192 73.0813L87.6111 73.0503C87.6057 73.0297 87.603 73.0194 87.603 73.0194C87.6236 73.014 87.6339 73.0113 87.6339 73.0113C87.66 73.0265 87.673 73.0341 87.673 73.0341C87.6882 73.0081 87.7062 72.9923 87.7268 72.9869C87.7214 72.9663 87.7393 72.9505 87.7806 72.9397C87.8219 72.9289 87.8268 72.9056 87.7953 72.8697L87.8572 72.8535L87.8882 72.8453L87.88 72.8144L87.8719 72.7834L87.9957 72.751C87.9957 72.751 88.0006 72.7276 88.0104 72.6809C88.0409 72.6288 88.0822 72.618 88.1343 72.6485L88.1261 72.6175C88.187 72.5133 88.2224 72.4379 88.2322 72.3912L88.2241 72.3602C88.2447 72.3548 88.255 72.3521 88.255 72.3521C88.2702 72.3261 88.2779 72.3131 88.2779 72.3131L88.2388 72.2902L88.2078 72.2983C88.2078 72.2983 88.1975 72.301 88.1769 72.3065C88.1769 72.3065 88.1742 72.2961 88.1688 72.2755C88.1634 72.2549 88.171 72.2418 88.1916 72.2364C88.1808 72.1952 88.1857 72.1718 88.2063 72.1664C88.1803 72.1512 88.1363 72.1517 88.0744 72.1679L88.0906 72.2298L88.084 72.3308L88.014 72.3161L87.983 72.3242L87.9912 72.3552L88.0302 72.378C88.0563 72.3932 88.0617 72.4139 88.0465 72.4399C88.0106 72.4714 87.9541 72.5082 87.877 72.5505C87.7999 72.5928 87.7618 72.6579 87.7628 72.7459L87.7319 72.754C87.7014 72.8061 87.6759 72.8349 87.6552 72.8403C87.5944 72.9445 87.546 73.0123 87.5101 73.0437C87.4949 73.0698 87.4954 73.1138 87.5116 73.1757L87.3944 73.1072L87.3325 73.1234L87.3097 73.1625L87.3797 73.1772L87.4107 73.1691C87.4161 73.1897 87.4085 73.2027 87.3878 73.2081C87.3878 73.2081 87.365 73.2472 87.3193 73.3254L87.2361 73.5126L87.0291 73.7323L87.0372 73.7633L87.0682 73.7552L87.2295 73.6136ZM87.2483 72.55C87.2787 72.4979 87.3043 72.4692 87.3249 72.4638L87.3706 72.3856L87.2777 72.41L87.2011 72.4962L87.1783 72.5353L87.2483 72.55ZM87.4081 72.2765C87.4342 72.2917 87.4445 72.289 87.4391 72.2684C87.4543 72.2424 87.4722 72.2266 87.4929 72.2212C87.5341 72.2104 87.5494 72.1843 87.5385 72.1431L87.5304 72.1121L87.4766 72.1593L87.4081 72.2765ZM88.9517 72.8641L89.1425 72.5825L89.1572 72.5125C89.1572 72.5125 89.1469 72.5152 89.1263 72.5206C89.1263 72.5206 89.129 72.5309 89.1344 72.5515L88.9126 72.8413L88.9208 72.8722L88.9517 72.8641ZM84.1916 69.9774L84.1835 69.9464L84.1134 69.9317L83.9668 70.0032L83.9749 70.0342L84.0059 70.0261L84.1378 70.0245L84.1916 69.9774ZM87.7684 71.8843L87.9135 71.6808L87.9054 71.6498L87.8745 71.658C87.818 71.6948 87.7799 71.76 87.7603 71.8533L87.7375 71.8924L87.7684 71.8843ZM89.211 72.4653C89.2469 72.4338 89.2952 72.366 89.3561 72.2618C89.3355 72.2672 89.3252 72.2699 89.3252 72.2699L89.1719 72.4425L89.1801 72.4734L89.211 72.4653ZM84.4833 69.7023L84.3514 69.7039L84.2667 69.7592C84.2927 69.7744 84.3264 69.7766 84.3677 69.7658L84.4833 69.7023ZM88.3154 72.204C88.31 72.1833 88.3176 72.1703 88.3382 72.1649C88.3535 72.1388 88.3638 72.1361 88.3692 72.1568C88.3898 72.1514 88.4078 72.1356 88.423 72.1096L88.4768 72.0624L88.4296 72.0086C88.4188 71.9673 88.403 71.9494 88.3824 71.9548C88.403 71.9494 88.4133 71.9467 88.4133 71.9467C88.5328 71.9815 88.6072 71.9289 88.6366 71.7889L88.6904 71.7417L88.767 71.6554C88.854 71.5665 88.9149 71.4623 88.9497 71.3429C88.9801 71.2908 89.0003 71.2414 89.0101 71.1947C89.0405 71.1426 89.071 71.0905 89.1014 71.0384C89.1221 71.033 89.127 71.0097 89.1161 70.9684L89.0461 70.9537C89.0309 70.9797 89.013 70.9954 88.9923 71.0009C88.9869 70.9802 88.9918 70.9569 89.007 70.9308C89.0277 70.9254 89.0277 70.9254 89.007 70.9308C89.0016 70.9102 88.9989 70.8999 88.9989 70.8999L88.968 70.908L88.8929 71.1262L88.901 71.1571C88.927 71.1724 88.9324 71.193 88.9172 71.219C88.9172 71.219 88.9069 71.2218 88.8863 71.2272C88.8244 71.2434 88.7733 71.3009 88.733 71.3997C88.708 71.4724 88.6748 71.5142 88.6336 71.525L88.6417 71.556C88.6221 71.6493 88.5683 71.6965 88.4803 71.6975L88.4184 71.7138C88.4086 71.7605 88.3983 71.7632 88.3875 71.7219L88.3174 71.7072C88.3174 71.7072 88.3022 71.7332 88.2718 71.7853C88.3185 71.7951 88.3472 71.8207 88.358 71.862C88.3895 71.8978 88.4079 71.9261 88.4133 71.9467C88.32 71.9271 88.2657 71.9303 88.2505 71.9563C88.2298 71.9617 88.2222 71.9748 88.2276 71.9954C88.2949 71.9998 88.3058 72.0411 88.2601 72.1192C88.2449 72.1453 88.24 72.1686 88.2454 72.1892C88.2508 72.2099 88.2562 72.2305 88.2616 72.2511L88.3398 72.2968L88.3154 72.204ZM89.4246 72.1446C89.4246 72.1446 89.5008 72.0144 89.653 71.7539C89.6736 71.7485 89.6839 71.7458 89.6839 71.7458C89.6785 71.7251 89.6758 71.7148 89.6758 71.7148L89.6139 71.731C89.553 71.8352 89.5226 71.8873 89.5226 71.8873L89.3546 72.1299L89.3709 72.1918L89.4018 72.1837L89.4246 72.1446ZM84.632 69.134C84.6114 69.1394 84.575 69.1269 84.5229 69.0965L84.5001 69.1355L84.6173 69.204L84.632 69.134ZM88.3393 70.9075L88.3849 70.8293C88.3643 70.8348 88.354 70.8375 88.354 70.8375L88.3002 70.8847L88.2855 70.9547L88.3393 70.9075ZM84.9776 68.8118L84.9076 68.7971C84.8815 68.7819 84.8609 68.7873 84.8457 68.8133C84.825 68.8187 84.8017 68.8138 84.7756 68.7986C84.7756 68.7986 84.7653 68.8013 84.7447 68.8067C84.7447 68.8067 84.7474 68.817 84.7528 68.8377C84.7528 68.8377 84.7555 68.848 84.7609 68.8686C84.7609 68.8686 84.7712 68.8659 84.7919 68.8605L84.8538 68.8443L84.9157 68.828L84.9776 68.8118ZM86.0493 68.8615L86.0021 68.8078L85.5606 68.8905L85.4987 68.9067C85.4835 68.9327 85.4656 68.9485 85.4449 68.9539C85.4395 68.9333 85.4265 68.9256 85.4058 68.9311C85.3494 68.9679 85.3081 68.9787 85.282 68.9635C85.2766 68.9429 85.2663 68.9456 85.2511 68.9716C85.2304 68.9771 85.2098 68.9825 85.1892 68.9879C85.1219 68.9835 85.0806 68.9943 85.0654 69.0204C85.0762 69.0616 85.061 69.0877 85.0197 69.0985L85.0116 69.0675L84.9644 69.0138C84.9644 69.0138 84.9541 69.0165 84.9334 69.0219C84.9334 69.0219 84.9361 69.0322 84.9416 69.0528L84.9578 69.1147L85.0197 69.0985C85.087 69.1029 85.1826 69.0889 85.3064 69.0564L86.0183 68.8697L86.0493 68.8615ZM83.335 67.7208L83.3888 67.6736C83.4095 67.6682 83.4171 67.6552 83.4117 67.6346L83.3807 67.6427L83.296 67.698C83.2753 67.7034 83.2677 67.7164 83.2731 67.7371L83.335 67.7208ZM83.8775 67.6447C83.8156 67.661 83.777 67.6821 83.7618 67.7082C83.7618 67.7082 83.7515 67.7109 83.7308 67.7163C83.7308 67.7163 83.7335 67.7266 83.739 67.7472L83.778 67.7701L83.8775 67.6447ZM87.3396 68.3577C87.2463 68.338 87.179 68.3337 87.1377 68.3445C87.091 68.3347 87.0264 68.3406 86.9439 68.3622L86.8819 68.3785L86.851 68.3866C86.7576 68.367 86.7033 68.3702 86.6881 68.3962C86.6729 68.4223 86.6653 68.4353 86.6653 68.4353C86.6599 68.4147 86.6572 68.4043 86.6572 68.4043C86.6724 68.3783 86.649 68.3734 86.5871 68.3896L86.4943 68.414L86.3395 68.4546C86.2874 68.4241 86.2461 68.435 86.2157 68.4871L86.1538 68.5033C86.1277 68.4881 86.0941 68.4859 86.0528 68.4967C86.0115 68.5075 85.9779 68.5053 85.9518 68.4901L85.8899 68.5063C85.9106 68.5009 85.9236 68.5085 85.929 68.5292L85.7433 68.5779C85.6607 68.5995 85.5858 68.6082 85.5185 68.6038C85.4772 68.6146 85.418 68.6411 85.3409 68.6834C85.279 68.6997 85.2117 68.6953 85.1389 68.6702L85.108 68.6784L85.0314 68.7646L85.0004 68.7727L85.0476 68.8265L85.2871 68.7306L85.2952 68.7616C85.3105 68.7355 85.3387 68.7171 85.38 68.7063L85.5119 68.7047L85.7905 68.6317L86.201 68.5571C86.3302 68.5452 86.4801 68.528 86.6506 68.5053C86.8417 68.4773 86.9888 68.4497 87.092 68.4226C87.1387 68.4324 87.2033 68.4265 87.2859 68.4049L87.3478 68.3886L87.3396 68.3577ZM83.5274 67.5711C83.7219 67.3878 83.8371 67.2804 83.8729 67.2489C83.8936 67.2435 83.9012 67.2305 83.8958 67.2099L84.119 67.0521L84.1419 67.013C84.1006 67.0238 84.08 67.0292 84.08 67.0292C84.0235 67.0661 83.9773 67.1003 83.9414 67.1317C83.9262 67.1578 83.911 67.1838 83.8958 67.2099L83.8339 67.2261C83.798 67.2576 83.7442 67.3047 83.6725 67.3677C83.6214 67.4252 83.56 67.4854 83.4883 67.5483L83.5274 67.5711ZM87.5299 68.7047L87.5218 68.6738L87.4127 68.6362C87.3508 68.6525 87.2525 68.6562 87.1179 68.6474C87.0712 68.6376 87.0169 68.6408 86.955 68.657C86.8931 68.6733 86.8388 68.6765 86.7921 68.6667L86.7612 68.6748C86.746 68.7009 86.715 68.709 86.6683 68.6992L86.3116 68.7266L86.2578 68.7738L86.2269 68.7819L86.134 68.8062C86.1134 68.8116 86.1058 68.8247 86.1112 68.8453C86.1372 68.8605 86.1812 68.86 86.2431 68.8438L86.4288 68.7951C86.4701 68.7842 86.558 68.7832 86.6927 68.792C86.7546 68.7758 86.8605 68.759 87.0103 68.7418C87.1808 68.7191 87.3231 68.7149 87.4371 68.7291L87.499 68.7129L87.5299 68.7047ZM84.016 67.5422L84.1774 67.4007C84.2132 67.3692 84.2491 67.3377 84.285 67.3063C84.3208 67.2748 84.354 67.233 84.3844 67.1809L84.5001 67.1175L84.5539 67.0703L84.5148 67.0475L84.461 67.0947L83.915 67.5356L83.9003 67.6057L83.9622 67.5894L84.016 67.5422ZM89.3612 70.0109L89.3597 69.8789L89.381 69.7079L89.3729 69.677C89.3729 69.677 89.3626 69.6797 89.3419 69.6851C89.3419 69.6851 89.3446 69.6954 89.3501 69.7161C89.2936 69.7529 89.2968 69.8072 89.3597 69.8789C89.3293 69.931 89.3194 69.9777 89.3303 70.019L89.3612 70.0109ZM84.832 67.626C84.8526 67.6205 84.9216 67.5473 85.039 67.4062L85.0227 67.3443L84.9918 67.3524L84.9608 67.3606L85.0146 67.3134L85.0847 67.3281L85.1156 67.32C85.1308 67.2939 85.133 67.2603 85.1222 67.219L85.0913 67.2271C85.0141 67.2694 84.9321 67.335 84.8451 67.424C84.7734 67.4869 84.7093 67.5368 84.6528 67.5737L84.6772 67.6665L84.832 67.626ZM89.4008 69.405C89.39 69.3637 89.3922 69.3301 89.4074 69.304L89.3993 69.2731L89.3455 69.3203L89.3308 69.3903C89.3416 69.4316 89.36 69.4598 89.3861 69.475L89.4008 69.405ZM85.2049 67.6605C85.1995 67.6398 85.2071 67.6268 85.2277 67.6214L85.2196 67.5904L85.2506 67.5823C85.2919 67.5715 85.3304 67.5503 85.3663 67.5189C85.3967 67.4668 85.438 67.456 85.4901 67.4864C85.4955 67.507 85.5058 67.5043 85.521 67.4783C85.5623 67.4675 85.6188 67.4306 85.6905 67.3677L85.7052 67.2977C85.6998 67.277 85.6765 67.2721 85.6352 67.2829L85.5733 67.2992L85.619 67.221L85.6499 67.2129L85.6956 67.1348C85.6543 67.1456 85.6337 67.151 85.6337 67.151L85.518 67.2144C85.4875 67.2665 85.4854 67.3002 85.5114 67.3154C85.5114 67.3154 85.5141 67.3257 85.5195 67.3464C85.5195 67.3464 85.5092 67.3491 85.4886 67.3545L85.1724 67.5366L85.1105 67.5529C85.1159 67.5735 85.1187 67.5838 85.1187 67.5838C85.1393 67.5784 85.1496 67.5757 85.1496 67.5757L85.1577 67.6067L85.2049 67.6605ZM87.5888 68.4247C87.6094 68.4192 87.617 68.4062 87.6116 68.3856L87.5416 68.3709C87.5156 68.3556 87.4949 68.3611 87.4797 68.3871C87.4591 68.3925 87.4384 68.3979 87.4178 68.4033L87.4259 68.4343L87.5888 68.4247ZM84.357 66.8242L84.3798 66.7851C84.4005 66.7797 84.4135 66.7873 84.4189 66.808L84.5184 66.6826L84.5021 66.6207L84.4712 66.6289L84.3946 66.7151C84.3022 66.7835 84.2408 66.8437 84.2104 66.8958L84.2185 66.9267C84.2033 66.9528 84.1956 66.9658 84.1956 66.9658C84.2163 66.9604 84.2266 66.9577 84.2266 66.9577L84.357 66.8242ZM85.6169 67.7178C85.6376 67.7124 85.6658 67.694 85.7017 67.6625C85.7582 67.6256 85.8016 67.5811 85.8321 67.529L85.9315 67.4037C85.988 67.3668 86.0467 67.2963 86.1076 67.1921L86.1305 67.153L86.0995 67.1612L86.0229 67.2474C86.0022 67.2528 85.9561 67.287 85.8844 67.3499C85.8637 67.3553 85.8355 67.3738 85.7996 67.4052C85.779 67.4106 85.7741 67.434 85.7849 67.4753L85.7621 67.5143C85.7414 67.5197 85.7159 67.5485 85.6854 67.6006C85.655 67.6527 85.6061 67.6765 85.5388 67.6721C85.5334 67.6515 85.5155 67.6672 85.485 67.7193C85.4644 67.7247 85.4595 67.7481 85.4703 67.7893L85.5403 67.8041L85.6169 67.7178ZM89.3359 69.1574L89.3506 69.0874C89.3397 69.0461 89.3289 69.0048 89.3181 68.9635C89.3225 68.8962 89.3117 68.855 89.2856 68.8397C89.2335 68.8093 89.2048 68.7837 89.1994 68.7631C89.22 68.7577 89.22 68.7577 89.1994 68.7631C89.1939 68.7425 89.1912 68.7322 89.1912 68.7322C89.1912 68.7322 89.1809 68.7349 89.1603 68.7403C89.1603 68.7403 89.163 68.7506 89.1684 68.7712C89.1738 68.7919 89.1689 68.8152 89.1537 68.8413C89.1591 68.8619 89.1748 68.8798 89.2009 68.895C89.2736 68.9201 89.3029 68.9896 89.2887 69.1036C89.2887 69.1036 89.2914 69.1139 89.2968 69.1345C89.2968 69.1345 89.3071 69.1318 89.3277 69.1264L89.3521 69.2193L89.3359 69.1574ZM88.7401 68.652L88.7239 68.5901C88.7239 68.5901 88.7212 68.5798 88.7158 68.5591C88.7104 68.5385 88.6973 68.5309 88.6767 68.5363L88.592 68.5916C88.6126 68.5862 88.6283 68.6041 88.6392 68.6454C88.6598 68.64 88.6728 68.6476 88.6782 68.6682L88.7254 68.722L88.7401 68.652ZM85.8209 67.2342C85.8818 67.13 85.9123 67.0779 85.9123 67.0779L85.8813 67.0861L85.7737 67.1804L85.8209 67.2342ZM88.5757 68.5297C88.5595 68.4678 88.5384 68.4292 88.5123 68.414L88.5042 68.383C88.4988 68.3624 88.4858 68.3548 88.4651 68.3602L88.4342 68.3683L88.3951 68.3455C88.3745 68.3509 88.3641 68.3536 88.3641 68.3536C88.3587 68.333 88.3663 68.32 88.387 68.3145C88.3968 68.2679 88.3783 68.2396 88.3317 68.2298C88.311 68.2352 88.2904 68.2406 88.2698 68.246C88.2643 68.2254 88.254 68.2281 88.2388 68.2542C88.2388 68.2542 88.2339 68.2775 88.2241 68.3242C88.2295 68.3448 88.2452 68.3627 88.2713 68.378C88.318 68.3878 88.3934 68.4231 88.4976 68.484C88.5389 68.4732 88.5649 68.4884 88.5757 68.5297ZM84.6843 66.9369C84.7049 66.9315 84.7256 66.926 84.7462 66.9206C84.7821 66.8892 84.8152 66.8474 84.8457 66.7953L85.0608 66.6065L85.2597 66.3559L85.3054 66.2777C85.2641 66.2885 85.2462 66.3043 85.2516 66.3249L85.0136 66.5527C84.9778 66.5842 84.8626 66.6916 84.6681 66.875L84.6452 66.914L84.6533 66.945L84.6843 66.9369ZM88.1835 68.1694L88.0353 68.109L88.0125 68.1481L88.1216 68.1857C88.1216 68.1857 88.1243 68.196 88.1297 68.2166C88.1297 68.2166 88.14 68.2139 88.1607 68.2085L88.1835 68.1694ZM89.0086 69.0447C89.0238 69.0187 89.0493 68.9899 89.0852 68.9585C89.121 68.927 89.1205 68.883 89.0837 68.8265L89.1065 68.7875L89.1131 68.6865C89.1229 68.6398 89.1354 68.6034 89.1506 68.5774C89.1865 68.5459 89.2175 68.5378 89.2435 68.553C89.2696 68.5683 89.2983 68.5938 89.3298 68.6297C89.3558 68.6449 89.3922 68.6574 89.4389 68.6672C89.4649 68.6824 89.4833 68.7107 89.4942 68.7519C89.4996 68.7726 89.5153 68.7905 89.5414 68.8057L89.5804 68.8286C89.575 68.8079 89.5723 68.7976 89.5723 68.7976C89.593 68.7922 89.6033 68.7895 89.6033 68.7895C89.6131 68.7428 89.6023 68.7015 89.5708 68.6657C89.5339 68.6092 89.5101 68.5603 89.4992 68.519C89.4938 68.4984 89.4781 68.4805 89.4521 68.4653C89.426 68.45 89.4054 68.4554 89.3902 68.4815L89.3592 68.4896L89.2257 68.3592C89.0847 68.2418 88.9805 68.1809 88.9132 68.1765C88.8719 68.1874 88.8388 68.2291 88.8137 68.3019C88.8408 68.405 88.8494 68.48 88.8396 68.5266C88.8048 68.6461 88.8345 68.7596 88.9289 68.8671L88.9614 68.9909L88.9776 69.0528L89.0086 69.0447ZM85.8341 67.0323L86.0493 66.8435L86.064 66.7735L86.0559 66.7425L86.0249 66.7506L85.8783 66.8222C85.8576 66.8276 85.8397 66.8433 85.8245 66.8694C85.8038 66.8748 85.8093 66.8954 85.8407 66.9313L85.7641 67.0176L85.7413 67.0566L85.8113 67.0713L85.8341 67.0323ZM84.6178 66.5573C84.6385 66.5519 84.664 66.5231 84.6944 66.4711C84.6836 66.4298 84.6912 66.4168 84.7173 66.432L84.7792 66.4157L84.7939 66.3457C84.8352 66.3349 84.8786 66.2904 84.9243 66.2123L84.9781 66.1651C85.0194 66.1543 85.0476 66.1358 85.0628 66.1098C85.0987 66.0783 85.1112 66.0419 85.1004 66.0007C85.0591 66.0115 85.0309 66.0299 85.0156 66.056L84.9619 66.1032C84.8739 66.1042 84.8201 66.1514 84.8005 66.2447C84.7701 66.2968 84.7548 66.3229 84.7548 66.3229C84.6473 66.4173 84.5859 66.4775 84.5706 66.5035C84.55 66.5089 84.5424 66.522 84.5478 66.5426L84.6178 66.5573ZM86.2578 66.7557L86.3573 66.6304L86.5871 66.3716L86.6556 66.2544L86.7094 66.2072L86.6475 66.2234C86.5149 66.3905 86.428 66.4795 86.3867 66.4903L86.3558 66.4985C86.3558 66.4985 86.3025 66.5896 86.1959 66.772C86.1959 66.772 86.1856 66.7747 86.165 66.7801C86.165 66.7801 86.1677 66.7904 86.1731 66.811L86.204 66.8029L86.2578 66.7557ZM85.3592 66.2305C85.4766 66.0895 85.5994 65.969 85.7276 65.8692L85.7423 65.7992L85.6804 65.8155L85.6038 65.9017L85.3201 66.2077L85.3282 66.2387L85.3592 66.2305ZM86.3167 66.4756C86.3265 66.4289 86.3493 66.3899 86.3852 66.3584C86.4417 66.3215 86.4802 66.3004 86.5009 66.295C86.5215 66.2896 86.5471 66.2608 86.5775 66.2087C86.5362 66.2195 86.5156 66.225 86.5156 66.225L86.2385 66.43L86.2548 66.4919L86.3167 66.4756ZM84.0485 65.648C84.0898 65.6372 84.1077 65.6214 84.1023 65.6008C84.1023 65.6008 84.2088 65.4185 84.422 65.0538L84.4514 64.9138L84.3651 64.8371C84.3032 64.8534 84.2647 64.8745 84.2494 64.9006C84.1886 65.0048 84.1559 65.0905 84.1515 65.1578L84.0632 65.578L84.0485 65.648ZM85.2734 65.5252C85.3039 65.4731 85.3294 65.4444 85.35 65.439L85.3419 65.408L85.311 65.4161C85.311 65.4161 85.2958 65.4422 85.2653 65.4943C85.2349 65.5464 85.2196 65.5724 85.2196 65.5724L85.2734 65.5252ZM86.8855 65.9956C86.8801 65.975 86.8671 65.9674 86.8464 65.9728C86.8258 65.9782 86.7976 65.9966 86.7617 66.0281C86.7465 66.0541 86.7443 66.0878 86.7551 66.1291L86.7632 66.16L86.8855 65.9956ZM85.9412 65.5486C85.9716 65.4965 86.0151 65.452 86.0716 65.4151C86.1227 65.3576 86.1711 65.2898 86.2167 65.2116L86.2086 65.1807C86.2086 65.1807 86.1983 65.1834 86.1777 65.1888C86.1777 65.1888 86.1804 65.1991 86.1858 65.2197C86.1141 65.2827 86.063 65.3402 86.0325 65.3923C85.976 65.4291 85.9456 65.4812 85.9412 65.5486L85.757 65.7292L85.7651 65.7602L85.7961 65.752L85.9412 65.5486ZM85.3922 65.7256L85.5307 65.6231L85.5992 65.5059L85.9513 65.0827L86.1421 64.8011C86.1986 64.7642 86.2242 64.7355 86.2188 64.7149C86.2079 64.6736 86.1765 64.6377 86.1244 64.6073L86.2563 64.6058L86.2873 64.5976L86.4781 64.316L86.4618 64.2541L86.3299 64.2556C86.3668 64.3121 86.3749 64.3431 86.3542 64.3485C86.3282 64.3333 86.3049 64.3284 86.2842 64.3338C86.2582 64.3186 86.2375 64.324 86.2223 64.35C86.2071 64.3761 86.2022 64.3994 86.2076 64.42L86.1782 64.5601L86.1244 64.6073L86.0544 64.5926C86.0239 64.6447 86.0114 64.681 86.0168 64.7017C86.0276 64.7429 86.0124 64.769 85.9711 64.7798L85.9564 64.8498C85.9879 64.8857 85.9623 64.9144 85.8798 64.9361C85.8852 64.9567 85.883 64.9904 85.8732 65.0371C85.858 65.0631 85.8373 65.0685 85.8113 65.0533C85.7852 65.0381 85.7646 65.0435 85.7494 65.0695C85.7342 65.0956 85.7162 65.1113 85.6956 65.1167L85.5652 65.2502L85.5814 65.3121C85.5868 65.3327 85.5819 65.3561 85.5667 65.3821C85.5721 65.4028 85.5618 65.4055 85.5358 65.3902C85.5097 65.375 85.4815 65.3935 85.451 65.4455C85.4358 65.4716 85.4179 65.4873 85.3972 65.4927C85.3972 65.4927 85.3896 65.5058 85.3744 65.5318C85.3744 65.5318 85.3874 65.5394 85.4135 65.5546L85.4216 65.5856L85.3906 65.5937C85.2983 65.662 85.2548 65.7065 85.2602 65.7272C85.2656 65.7478 85.2504 65.7739 85.2146 65.8053C85.1939 65.8107 85.1733 65.8161 85.1527 65.8215C85.1581 65.8422 85.1401 65.8579 85.0989 65.8687C85.0684 65.9208 85.0532 65.9469 85.0532 65.9469C85.0738 65.9415 85.0999 65.9567 85.1313 65.9926C85.1574 66.0078 85.1883 65.9997 85.2242 65.9682L85.3922 65.7256ZM84.7772 64.8945C84.8228 64.8163 84.8457 64.7773 84.8457 64.7773L84.8949 64.3343L84.8787 64.2724L84.6899 64.0572C84.653 64.0007 84.6194 63.9985 84.5889 64.0506C84.4878 64.2536 84.4485 64.4403 84.4712 64.6108C84.5558 64.7651 84.6344 64.8547 84.7071 64.8798C84.7126 64.9004 84.7359 64.9053 84.7772 64.8945ZM87.2656 65.3004C87.2135 65.27 87.1874 65.2548 87.1874 65.2548L87.1336 65.302L87.1123 65.473L87.1433 65.4648L87.2656 65.3004ZM86.2934 65.1254C86.3292 65.0939 86.3624 65.0521 86.3928 65C86.4233 64.9479 86.4743 64.8904 86.546 64.8275L86.5755 64.6875L86.5217 64.7346L86.2543 65.1025C86.2543 65.1025 86.257 65.1128 86.2624 65.1335C86.2624 65.1335 86.2521 65.1362 86.2314 65.1416L86.2934 65.1254ZM84.8137 64.0248C84.7975 63.9628 84.7763 63.9243 84.7503 63.9091C84.7503 63.9091 84.7242 63.8938 84.6721 63.8634L84.6884 63.9253L84.7518 64.041L84.8218 64.0557L84.8137 64.0248ZM87.2752 65.4633C87.2904 65.4373 87.3823 65.325 87.5508 65.1264C87.5714 65.121 87.579 65.1079 87.5736 65.0873L87.5655 65.0564C87.5242 65.0672 87.5063 65.0829 87.5117 65.1036L87.3894 65.268L87.2443 65.4714L87.2524 65.5024L87.2752 65.4633ZM86.0072 64.5388C86.0018 64.5181 86.0018 64.5181 86.0072 64.5388C86.0278 64.5334 86.0354 64.5203 86.03 64.4997L86.1523 64.3353C86.1469 64.3147 86.1545 64.3016 86.1751 64.2962L86.1361 64.2734C86.0752 64.3776 86.0268 64.4454 85.9909 64.4769L86.0072 64.5388ZM87.4335 65.0579C87.464 65.0058 87.4792 64.9797 87.4792 64.9797L87.432 64.926C87.4114 64.9314 87.3858 64.9601 87.3554 65.0122L87.4335 65.0579ZM87.7268 64.9148C87.7214 64.8942 87.7084 64.8865 87.6878 64.892C87.6671 64.8974 87.6416 64.9261 87.6111 64.9782L87.6502 65.0011L87.7268 64.9148ZM86.7287 64.5149L86.8738 64.3115C86.8738 64.3115 86.8891 64.2854 86.9195 64.2333L86.8576 64.2496L86.6897 64.4921L86.6978 64.5231L86.7287 64.5149ZM86.2208 64.2181L86.3578 63.9837C86.3784 63.9782 86.386 63.9652 86.3806 63.9446L86.3497 63.9527L86.1817 64.1953L86.1898 64.2262L86.2208 64.2181ZM87.7725 64.8366C87.7931 64.8312 87.8007 64.8182 87.7953 64.7976L87.8948 64.6722L87.8867 64.6413L87.8557 64.6494L87.7253 64.7829L87.7725 64.8366ZM87.701 64.69C87.7053 64.6227 87.7358 64.5706 87.7923 64.5337C87.7869 64.5131 87.7945 64.5001 87.8151 64.4946L87.7451 64.4799C87.6734 64.5428 87.6223 64.6004 87.5919 64.6525C87.5712 64.6579 87.5636 64.6709 87.569 64.6915C87.5744 64.7122 87.5695 64.7355 87.5543 64.7615L87.6472 64.7372L87.6781 64.7291L87.701 64.69ZM86.988 64.1161C87.0185 64.064 87.044 64.0352 87.0646 64.0298L87.0565 63.9989L87.0027 64.0461C87.0027 64.0461 86.9875 64.0721 86.9571 64.1242L86.988 64.1161ZM87.7989 64.4327C87.8195 64.4273 87.8451 64.3986 87.8755 64.3465C87.8549 64.3519 87.8446 64.3546 87.8446 64.3546C87.8391 64.334 87.8364 64.3236 87.8364 64.3236C87.7952 64.3345 87.7799 64.3605 87.7908 64.4018C87.7701 64.4072 87.7625 64.4202 87.7679 64.4409C87.7886 64.4354 87.7989 64.4327 87.7989 64.4327ZM86.5237 64.2379C86.6259 64.1229 86.6895 64.029 86.7145 63.9563L86.783 63.839C87.0124 63.5363 87.1369 63.3382 87.1565 63.2449C87.1717 63.2188 87.1663 63.1982 87.1403 63.1829C87.1294 63.1417 87.1137 63.1237 87.0931 63.1292C87.0876 63.1085 87.0746 63.1009 87.054 63.1063L87.0459 63.0754L87.0149 63.0835L87.0312 63.1454L87.0393 63.1763C86.998 63.1872 86.9801 63.2029 86.9855 63.2235L86.5044 63.9121L86.5126 63.9431L86.5435 63.9349L86.5973 63.8878L86.6135 63.9497C86.6244 63.9909 86.6195 64.0143 86.5988 64.0197L86.5679 64.0278C86.4962 64.0907 86.45 64.1249 86.4293 64.1303L86.4146 64.2003C86.4353 64.1949 86.4586 64.1998 86.4847 64.215C86.5107 64.2303 86.5237 64.2379 86.5237 64.2379ZM86.5567 63.733C86.5916 63.6136 86.6524 63.5094 86.7394 63.4204L86.7313 63.3895L86.7003 63.3976C86.7003 63.3976 86.6394 63.5018 86.5176 63.7102C86.5176 63.7102 86.5203 63.7205 86.5258 63.7411C86.5258 63.7411 86.5154 63.7438 86.4948 63.7492L86.5567 63.733ZM87.2554 63.7482C87.3315 63.618 87.3696 63.5529 87.3696 63.5529L87.3615 63.5219L87.3305 63.53L87.2082 63.6944L87.2164 63.7254L87.2554 63.7482ZM88.2114 63.8614C88.2419 63.8093 88.2571 63.7832 88.2571 63.7832C88.2463 63.742 88.2512 63.7186 88.2718 63.7132L88.3713 63.5879L88.3241 63.5341L88.254 63.5194C88.2128 63.5302 88.1976 63.5562 88.2084 63.5975C88.2246 63.6594 88.1915 63.7012 88.1089 63.7228L88.0942 63.7929L88.2114 63.8614ZM88.2911 64.039L88.3058 63.969L88.4509 63.7655C88.5575 63.5831 88.6108 63.492 88.6108 63.492C88.6771 63.4084 88.7304 63.3172 88.7706 63.2185L88.7544 63.1566L88.6925 63.1728C88.6316 63.277 88.5962 63.3524 88.5864 63.3991L88.5555 63.4072C88.5663 63.4485 88.5336 63.5343 88.4575 63.6645L88.2439 63.9852C88.2233 63.9906 88.2157 64.0036 88.2211 64.0243C88.2265 64.0449 88.2216 64.0682 88.2063 64.0943C88.227 64.0889 88.24 64.0965 88.2454 64.1171L88.2911 64.039ZM86.6338 63.018L86.9307 62.5101L86.9454 62.4401L86.9145 62.4482C86.9145 62.4482 86.9041 62.4509 86.8835 62.4563C86.8835 62.4563 86.8862 62.4666 86.8916 62.4873C86.8916 62.4873 86.8307 62.5915 86.7089 62.7998L86.5719 63.0343C86.5513 63.0397 86.5437 63.0527 86.5491 63.0733L86.5801 63.0652L86.6338 63.018ZM87.6974 63.0368L87.6893 63.0059L87.6583 63.014L87.5589 63.1393L87.567 63.1703L87.5979 63.1621L87.6974 63.0368ZM88.4626 63.4316C88.4518 63.3903 88.4567 63.367 88.4773 63.3616C88.5697 63.2932 88.6077 63.2281 88.5915 63.1662L88.5834 63.1353L88.5524 63.1434L88.4839 63.2606C88.4633 63.266 88.4557 63.279 88.4611 63.2997C88.4665 63.3203 88.4692 63.3306 88.4692 63.3306C88.4486 63.336 88.4154 63.3778 88.3697 63.4559L88.3469 63.495L88.4169 63.5097L88.4626 63.4316ZM87.2559 63.1195L87.2935 63.0104L87.3163 62.9713C87.3782 62.9551 87.4163 62.89 87.4305 62.776C87.4457 62.7499 87.4659 62.7006 87.4909 62.6278C87.5366 62.5497 87.5876 62.4922 87.6441 62.4553L87.6588 62.3853C87.6588 62.3853 87.6328 62.3701 87.5807 62.3396L87.5188 62.3558C87.4938 62.4286 87.4682 62.4573 87.4422 62.4421L87.4112 62.4502C87.422 62.4915 87.4122 62.5382 87.3818 62.5903C87.3513 62.6424 87.3361 62.6684 87.3361 62.6684C87.2948 62.6792 87.3003 62.6999 87.3524 62.7303L87.3995 62.7841L87.2986 62.7775L87.2367 62.7937L87.2839 62.8475L87.331 62.9013L87.3001 62.9094L87.2301 62.8947C87.2138 62.8328 87.1802 62.8306 87.1291 62.8881L87.1144 62.9582C87.0992 62.9842 87.097 63.0179 87.1078 63.0591L87.225 63.1276L87.2559 63.1195ZM85.2318 64.6098C85.4774 64.369 85.6459 64.1704 85.7372 64.0141C85.6861 64.0716 85.984 63.6516 86.6308 62.7542L86.9586 62.2381C87.0097 62.1806 87.0553 62.1025 87.0956 62.0037C87.1511 61.8789 87.2147 61.785 87.2864 61.7221C87.3168 61.67 87.3239 61.613 87.3077 61.5511C87.3077 61.5511 87.3229 61.525 87.3534 61.4729C87.3828 61.3329 87.4051 61.2498 87.4204 61.2238C87.4454 61.151 87.427 61.1228 87.365 61.139C87.2619 61.1661 87.2331 61.1406 87.2788 61.0624L87.2935 60.9924L87.2773 60.9305C87.2773 60.9305 87.2669 60.9332 87.2463 60.9386C87.2463 60.9386 87.249 60.9489 87.2544 60.9696L87.0733 61.4141C87.0733 61.4141 87.0787 61.4347 87.0895 61.476L87.0976 61.5069L86.9687 61.7723L86.9068 61.7885L86.8987 61.7576L86.9134 61.6876L86.9053 61.6566L86.8744 61.6647C86.8798 61.6854 86.8619 61.7011 86.8206 61.7119L86.8744 61.6647L86.8891 61.5947L87.1829 60.8229L87.4325 60.2612C87.4772 60.0951 87.4806 59.9398 87.4427 59.7954C87.4004 59.7182 87.3483 59.6878 87.2864 59.704C86.9769 59.7852 86.7526 59.8551 86.6136 59.9136C86.4691 59.9515 86.2372 60.0344 85.9179 60.1622L85.5936 60.3134C85.5165 60.3557 85.4784 60.4209 85.4795 60.5088C85.4903 60.5501 85.507 60.656 85.5297 60.8265C85.5524 60.9969 85.5517 61.1625 85.5277 61.3232C85.5189 61.4579 85.4759 61.5463 85.3988 61.5886L85.2684 61.7221C85.2792 61.7633 85.2846 61.784 85.2846 61.784L85.5206 62.0529C85.6247 62.1138 85.6567 62.1936 85.6165 62.2924L85.5104 62.5187C85.4593 62.5762 85.393 62.6598 85.3115 62.7694C85.2452 62.8529 85.1686 62.9392 85.0816 63.0282C84.9382 63.154 84.8343 63.3467 84.7701 63.6061C84.7548 63.6322 84.7553 63.6762 84.7716 63.7381C84.7824 63.7793 84.8193 63.8358 84.8822 63.9075L85.1618 64.5951C85.1726 64.6364 85.196 64.6413 85.2318 64.6098ZM87.735 62.9277C87.7762 62.9169 87.8018 62.8881 87.8116 62.8415C87.8214 62.7948 87.8133 62.7638 87.7872 62.7486C87.8545 62.753 87.898 62.7085 87.9176 62.6151C87.9383 62.6097 87.9459 62.5967 87.9405 62.5761C87.9351 62.5554 87.94 62.5321 87.9552 62.506C87.94 62.5321 87.922 62.5478 87.9014 62.5532C87.8808 62.5586 87.8731 62.5717 87.8786 62.5923C87.8786 62.5923 87.8481 62.6444 87.7872 62.7486C87.7828 62.8159 87.7524 62.868 87.6959 62.9049L87.704 62.9358L87.735 62.9277ZM88.4271 63.0439C88.4271 63.0439 88.4651 62.9788 88.5413 62.8486C88.5511 62.8019 88.5864 62.7264 88.6473 62.6222L88.693 62.5441L88.6001 62.5685L88.5154 62.6238L88.3489 62.9982L88.3571 63.0292C88.3571 63.0292 88.3598 63.0395 88.3652 63.0602C88.3858 63.0547 88.4064 63.0493 88.4271 63.0439ZM88.8833 62.8912C88.9245 62.8804 88.9528 62.8619 88.968 62.8359L89.0741 62.6096L89.1197 62.5314L89.0416 62.4857L89.0187 62.5248L88.9893 62.6649L88.9355 62.7121L88.898 62.8212L88.8833 62.8912ZM88.0399 62.4507C88.2064 62.0763 88.3151 61.8603 88.3662 61.8028C88.3608 61.7821 88.3684 61.7691 88.389 61.7637L88.3271 61.7799L88.2358 61.9362L87.9699 62.436L87.9861 62.4979L88.0252 62.5208L88.0399 62.4507ZM88.7549 62.5279C88.7647 62.4812 88.7799 62.4551 88.8006 62.4497C88.8364 62.4183 88.8516 62.3922 88.8462 62.3716C88.8604 62.2576 88.8828 62.1745 88.9132 62.1224C88.9338 62.117 88.9387 62.0937 88.9279 62.0524L88.8579 62.0377L88.7666 62.194C88.7057 62.2982 88.6752 62.3503 88.6752 62.3503C88.6295 62.4284 88.6458 62.4903 88.7239 62.536L88.7549 62.5279ZM87.2199 61.3425L87.2037 61.2806C87.2091 61.3012 87.2015 61.3143 87.1809 61.3197C87.1754 61.299 87.1754 61.299 87.1809 61.3197C87.1809 61.3197 87.1504 61.3718 87.0895 61.476L87.2199 61.3425ZM89.2177 62.2742C89.2383 62.2687 89.2486 62.266 89.2486 62.266C89.2432 62.2454 89.2405 62.2351 89.2405 62.2351C89.2351 62.2144 89.2221 62.2068 89.2014 62.2122L89.1867 62.2823L89.0872 62.4076L89.1035 62.4695L89.1654 62.4533L89.2177 62.2742ZM89.0629 62.3147C89.0933 62.2627 89.1292 62.2312 89.1705 62.2204L89.1623 62.1894L89.1314 62.1975L89.0238 62.2919L89.0319 62.3229L89.0629 62.3147ZM89.3237 62.0478L89.2846 62.025L89.2308 62.0722L89.278 62.126L89.3237 62.0478ZM87.7045 62.3071C87.7045 62.3071 87.7578 62.216 87.8644 62.0336C87.8948 61.9815 87.8894 61.9609 87.8481 61.9717C87.8481 61.9717 87.8584 61.969 87.8791 61.9636C87.8737 61.943 87.8709 61.9327 87.8709 61.9327C87.8916 61.9272 87.9019 61.9245 87.9019 61.9245C87.9215 61.8312 87.952 61.7791 87.9932 61.7682C88.0237 61.7162 88.0362 61.6798 88.0308 61.6591L88.0993 61.5419C88.0939 61.5213 88.1064 61.4849 88.1368 61.4328C88.127 61.4795 88.195 61.3183 88.3408 60.9493C88.3561 60.9232 88.3686 60.8868 88.3784 60.8402C88.4088 60.7881 88.4447 60.7566 88.486 60.7458L88.5088 60.7067C88.498 60.6654 88.5078 60.6188 88.5382 60.5667L88.5824 60.3566L88.5742 60.3256C88.5536 60.331 88.546 60.3441 88.5514 60.3647L88.491 60.5129L88.4372 60.5601L88.421 60.4982C88.4406 60.4048 88.445 60.3375 88.4342 60.2962L88.4261 60.2653C88.4261 60.2653 88.4158 60.268 88.3951 60.2734C88.3951 60.2734 88.3978 60.2837 88.4032 60.3043C88.3728 60.3564 88.3527 60.4058 88.3429 60.4525C88.3331 60.4992 88.3232 60.5459 88.3134 60.5925L88.3215 60.6235L88.1242 61.0061C88.0937 61.0582 88.0839 61.1049 88.0947 61.1461L88.0572 61.2552C88.0115 61.3334 87.9784 61.3752 87.9577 61.3806L87.8958 61.3968C87.8806 61.4229 87.8529 61.4853 87.8126 61.584C87.7669 61.6622 87.7576 61.7529 87.7847 61.856L87.77 61.9261L87.7228 61.8723L87.7147 61.8413C87.694 61.8467 87.6864 61.8598 87.6918 61.8804C87.7135 61.9629 87.6934 62.0123 87.6314 62.0286C87.6108 62.034 87.5853 62.0627 87.5548 62.1148C87.6221 62.1192 87.6509 62.1448 87.6411 62.1914C87.6259 62.2175 87.621 62.2408 87.6264 62.2615L87.6426 62.3234L87.7045 62.3071ZM88.9883 61.9042C89.0187 61.8521 89.0313 61.8158 89.0259 61.7951C89.0617 61.7637 89.0894 61.7013 89.1091 61.6079C89.1297 61.6025 89.1297 61.6025 89.1091 61.6079C89.1037 61.5873 89.101 61.577 89.101 61.577L89.07 61.5851C89.0243 61.6632 88.9944 61.7593 88.9802 61.8733C88.9595 61.8787 88.9519 61.8917 88.9573 61.9124L88.9883 61.9042ZM89.4206 61.0299C89.4511 60.9779 89.4663 60.9518 89.4663 60.9518L89.4353 60.9599L89.3963 60.9371C89.3909 60.9165 89.3778 60.9088 89.3572 60.9143L89.3653 60.9452L89.3734 60.9762L89.4206 61.0299ZM88.7244 59.8893L88.7376 59.6873C88.7322 59.6667 88.7192 59.6591 88.6986 59.6645L88.6676 59.6726C88.6893 59.7551 88.6979 59.8301 88.6935 59.8974L88.7326 59.9202L88.7244 59.8893ZM87.1164 58.4253C87.111 58.4047 87.098 58.3971 87.0774 58.4025L86.8135 58.4055L86.8216 58.4365L86.7287 58.4608L86.7059 58.4999L86.7678 58.4837C86.8091 58.4729 86.8428 58.4751 86.8688 58.4903L87.0855 58.4334L87.1164 58.4253ZM87.563 58.1097C87.4902 58.0847 87.4023 58.0857 87.2991 58.1128C87.1905 58.1192 87.1156 58.1278 87.0743 58.1386L86.8414 58.1336L86.7942 58.0798L86.8399 58.0016L86.9018 57.9854L87.4376 58.0103C87.4583 58.0048 87.4816 58.0097 87.5076 58.025C87.5543 58.0348 87.588 58.037 87.6086 58.0316L87.6558 58.0853L87.5939 58.1016L87.563 58.1097ZM96.1875 73.4474C96.1256 73.4637 96.0609 73.4696 95.9936 73.4652C95.9469 73.4554 95.8926 73.4586 95.8307 73.4748C95.7841 73.465 95.7325 73.4786 95.676 73.5154C95.6141 73.5317 95.5391 73.5403 95.4512 73.5413L95.0473 73.5149L94.9854 73.5312C94.9431 73.454 94.8753 73.4057 94.7819 73.386C94.6885 73.3664 94.6158 73.3414 94.5637 73.3109C94.4703 73.2913 94.3873 73.269 94.3146 73.244C94.257 73.1929 94.1946 73.1651 94.1273 73.1607C94.0959 73.1249 94.0541 73.0917 94.002 73.0613C93.9499 73.0308 93.8951 72.9901 93.8376 72.939L93.9076 72.9537L93.3819 72.463C93.23 72.3044 93.0739 72.0035 92.9136 71.5603L92.741 71.4071C92.715 71.3918 92.6993 71.3739 92.6938 71.3533C92.7037 71.3066 92.7059 71.2729 92.7004 71.2523C92.5726 70.933 92.4951 70.7217 92.468 70.6185C92.3977 70.3503 92.3512 70.1309 92.3285 69.9604C92.4239 70.1559 92.4851 70.3053 92.5122 70.4085L92.5431 70.4003C92.5053 70.2559 92.4332 70.0653 92.327 69.8285L92.296 69.8366C92.3069 69.8779 92.3047 69.9115 92.2894 69.9376C92.2211 69.8452 92.1572 69.6855 92.0976 69.4585C92.0327 69.2109 91.9916 69.0122 91.9743 68.8623C91.9625 68.7331 91.9329 68.41 91.8855 67.8931C91.8899 67.8258 91.8862 67.7276 91.8744 67.5983C91.8778 67.4431 91.8686 67.3241 91.847 67.2416C91.8307 67.1797 91.8042 67.1205 91.7673 67.064C91.7457 66.9815 91.7343 66.8962 91.7333 66.8083C91.7479 66.2751 91.7971 65.8321 91.881 65.4793C91.9354 65.2665 91.9557 65.0076 91.9419 64.7025C91.9615 64.6091 91.9811 64.5157 92.0007 64.4224C92.0356 64.3029 92.0677 64.1732 92.0971 64.0332C92.1168 63.9398 92.1234 63.8388 92.1169 63.7302C92.1257 63.5956 92.1475 63.4686 92.1824 63.3491C92.2108 63.1211 92.2375 62.9708 92.2626 62.898C92.2724 62.8514 92.2665 62.7868 92.2448 62.7042L92.2367 62.6733L92.431 62.0268L92.6741 61.5661C92.7742 61.2751 92.8368 61.0933 92.8618 61.0206C92.9325 60.8697 93.0163 60.7264 93.113 60.5908C93.2304 60.4497 93.3245 60.3038 93.3952 60.1529L93.7767 59.5896C93.9137 59.3552 94.0491 59.1984 94.1827 59.1193C94.613 58.7417 94.9411 58.4792 95.1671 58.3317L95.3432 58.1201C95.4301 58.0312 95.5664 57.9623 95.7522 57.9136L96.394 57.7122C96.5179 57.6797 96.5994 57.5701 96.6386 57.3834L96.6747 57.1423L96.6975 57.1033L96.7284 57.0951C96.7904 57.0789 96.8501 57.0963 96.9076 57.1474C96.9803 57.1724 97.0351 57.2132 97.072 57.2697L97.2054 57.4001C97.2477 57.4772 97.3079 57.5386 97.3861 57.5843C97.4642 57.63 97.5293 57.668 97.5814 57.6985C97.6021 57.6931 97.6151 57.7007 97.6205 57.7213C97.59 57.7734 97.6063 57.8353 97.6692 57.907C97.68 57.9483 97.7169 58.0048 97.7798 58.0765L97.8027 58.0374C97.8125 57.9908 97.8038 57.9158 97.7768 57.8127L97.8306 57.7655L98.3745 57.8213C98.4625 57.8203 98.5347 57.8013 98.5912 57.7645C98.6064 57.7384 98.6347 57.72 98.6759 57.7091C98.7378 57.6929 98.7818 57.6924 98.8079 57.7076C98.8546 57.7174 98.9012 57.7272 98.9479 57.7371L98.987 57.7599C99.1108 57.7274 99.1292 57.7557 99.0423 57.8446L99.399 57.8172C99.5858 57.8565 99.7182 57.8989 99.7963 57.9446C99.9526 58.0359 100.046 58.0995 100.078 58.1354C100.115 58.1919 100.172 58.243 100.25 58.2886C100.329 58.3343 100.394 58.3724 100.446 58.4028L100.478 58.5266C100.603 58.5821 100.699 58.612 100.767 58.6164C100.834 58.6208 100.89 58.584 100.936 58.5058C100.963 58.609 101.003 58.6758 101.055 58.7062C101.127 58.7313 101.177 58.7514 101.203 58.7666C101.296 58.7862 101.351 58.827 101.367 58.8889C101.378 58.9302 101.386 58.9611 101.392 58.9818L101.447 59.0665C101.662 59.2969 101.81 59.5668 101.891 59.8764L102.092 60.5183C102.179 60.8484 102.242 61.3393 102.28 61.9908L102.297 62.8133C102.291 63.1239 102.296 63.3541 102.313 63.504L102.341 63.8607L102.326 63.9307L102.293 63.8069L102.226 64.056C102.212 64.17 102.188 64.3307 102.154 64.5381C102.136 64.7194 102.094 64.9398 102.03 65.1993C101.835 65.8017 101.705 66.1887 101.64 66.3603C101.576 66.6197 101.493 66.8509 101.392 67.0539L101.416 67.1468C101.457 67.1359 101.475 67.1202 101.47 67.0996C101.49 67.0942 101.537 67.06 101.608 66.9971C101.579 67.1371 101.526 67.2283 101.448 67.2706C101.238 67.392 101.113 67.5901 101.075 67.8648C101.087 67.994 101.045 68.1704 100.949 68.394C100.462 69.2275 100.218 69.6443 100.218 69.6443C100.218 69.6443 100.021 69.9829 99.6248 70.6602C99.6095 70.6862 99.6073 70.7199 99.6182 70.7611C99.6236 70.7818 99.6187 70.8051 99.6035 70.8312L99.5512 71.0103L99.4857 71.3914C99.415 71.5422 99.3146 71.5796 99.1843 71.5035L99.0362 71.4431L98.9824 71.4903C98.7855 71.9169 98.6669 72.1796 98.6267 72.2783L98.5825 72.4884L98.5044 72.4427C98.5044 72.4427 98.4891 72.4688 98.4587 72.5209L98.3983 72.6691L98.2664 72.6706C98.2251 72.6814 98.1664 72.7519 98.0903 72.8822C98.0957 72.9028 98.0778 72.9185 98.0365 72.9294C98.0159 72.9348 98.0056 72.9375 98.0056 72.9375C97.9481 72.8864 97.8911 72.8793 97.8346 72.9162C97.7781 72.953 97.7292 72.9769 97.6879 72.9877C97.5337 73.0723 97.3789 73.1129 97.2236 73.1095C97.203 73.1149 97.1514 73.1284 97.0689 73.1501C97.007 73.1663 96.9608 73.2005 96.9303 73.2526C96.8945 73.2841 96.8353 73.3106 96.7527 73.3323L96.1875 73.4474ZM93.0166 71.0701C93.0112 71.0495 92.977 71.0033 92.9141 70.9316L92.8831 70.9397C92.9613 70.9854 93.0057 71.0289 93.0166 71.0701ZM94.9981 71.9399C95.0133 71.9138 95.0236 71.9111 95.029 71.9318C95.0496 71.9263 95.0703 71.9209 95.0909 71.9155L95.469 71.7171C95.4169 71.6867 95.3805 71.6742 95.3599 71.6796C95.3186 71.6904 95.2567 71.7066 95.1741 71.7283C95.0862 71.7293 95.014 71.7482 94.9575 71.7851C94.9216 71.8166 94.8521 71.8458 94.7489 71.8729C94.661 71.8739 94.5887 71.8928 94.5322 71.9297C94.491 71.9405 94.4367 71.9438 94.3694 71.9394C94.3227 71.9296 94.2971 71.9583 94.2927 72.0256L94.2618 72.0337C94.1738 72.0348 94.0365 72.0156 93.8498 71.9764L93.5615 71.8866C93.6245 71.9583 93.7026 72.004 93.796 72.0236C93.8014 72.0442 93.8198 72.0725 93.8513 72.1083C93.8773 72.1236 93.9056 72.1051 93.936 72.053C93.9675 72.0889 94.0038 72.1014 94.0451 72.0906C94.107 72.0743 94.1407 72.0765 94.1461 72.0972C94.1721 72.1124 94.2058 72.1146 94.2471 72.1038L94.5647 72.0535L94.4866 72.0079L94.8205 72.0195L94.9981 71.9399ZM95.164 72.1941C95.1119 72.1636 95.0652 72.1538 95.0239 72.1647L95.0321 72.1956L95.164 72.1941ZM93.7006 71.1554L93.5215 71.1031C93.579 71.1542 93.6207 71.1874 93.6468 71.2026L93.7087 71.1863L93.7006 71.1554ZM93.3601 71.2447L93.3439 71.1828C93.3645 71.1774 93.3775 71.185 93.3829 71.2056C93.4036 71.2002 93.4269 71.2051 93.453 71.2203C93.4107 71.1432 93.3374 71.0742 93.2332 71.0133C93.1497 70.947 93.1101 70.8802 93.1145 70.8129L93.0282 70.7363C93.0228 70.7156 93.0098 70.708 92.9892 70.7134C92.9729 70.6515 92.9518 70.6129 92.9257 70.5977L93.0658 70.6272C92.9768 70.5402 92.9323 70.4967 92.9323 70.4967C92.864 70.4044 92.793 70.3017 92.7192 70.1887L92.6883 70.1969C92.6622 70.1816 92.6465 70.1637 92.6411 70.1431C92.6303 70.1018 92.6118 70.0736 92.5858 70.0583L92.6101 70.1512L92.6182 70.1821L92.6883 70.1969C92.673 70.2229 92.6736 70.2669 92.6898 70.3288C92.706 70.3907 92.7564 70.4988 92.841 70.653C92.8681 70.7562 92.8946 70.8154 92.9207 70.8306C93.0259 70.9795 93.162 71.1202 93.3291 71.2528L93.3601 71.2447ZM94.7621 71.6709C94.8653 71.6439 94.9505 71.6325 95.0179 71.6369L95.0097 71.606L94.4267 71.5273L94.8255 71.7866L94.7621 71.6709ZM94.1857 71.4913L94.2557 71.506C94.411 71.5094 94.4962 71.4981 94.5114 71.472C94.5679 71.4352 94.6195 71.4216 94.6662 71.4314C94.7335 71.4358 94.7851 71.4223 94.821 71.3908C94.8568 71.3594 94.916 71.3328 94.9986 71.3112C95.0811 71.2895 95.1403 71.263 95.1762 71.2315L95.2462 71.2462L95.3847 71.1437L95.4923 71.0493L95.4842 71.0184C95.5048 71.013 95.5304 70.9842 95.5608 70.9321L94.0685 71.4228L94.0213 71.369C94.0267 71.3896 94.0294 71.4 94.0294 71.4L93.3063 71.2919C93.3063 71.2919 93.3975 71.3452 93.5798 71.4517C93.6319 71.4822 93.6813 71.5023 93.728 71.5121C93.7953 71.5165 93.8523 71.5236 93.899 71.5334L93.7833 71.5968L93.8924 71.6344L94.0162 71.6019L94.2491 71.607L94.1857 71.4913ZM95.163 71.4335C95.2097 71.4433 95.2303 71.4379 95.2249 71.4172C95.2141 71.376 95.2059 71.345 95.2005 71.3244L95.031 71.435L95.163 71.4335ZM94.9879 72.4057C95.0498 72.3895 95.1351 72.3781 95.2437 72.3717C95.3675 72.3392 95.4576 72.3045 95.5141 72.2677C96.1985 71.9338 96.688 71.5297 96.9826 71.0554L97.012 70.9154L96.9354 71.0017L96.9045 71.0098C96.8534 71.0673 96.8023 71.1248 96.7512 71.1823C96.7208 71.2344 96.6903 71.2865 96.6599 71.3386C96.5817 71.2929 96.5665 71.319 96.6142 71.4167C96.5936 71.4221 96.5729 71.4275 96.5523 71.433C96.5263 71.4177 96.5056 71.4232 96.4904 71.4492L96.1514 71.6704L96.1367 71.7405C96.0748 71.7567 96.0259 71.7805 95.9901 71.812C95.9488 71.8228 95.8923 71.8597 95.8206 71.9226L95.5745 72.1195C95.4974 72.1618 95.4278 72.191 95.3659 72.2073C95.3193 72.1975 95.2753 72.198 95.234 72.2088L95.2031 72.2169C95.1412 72.2332 95.1026 72.2543 95.0874 72.2804L95.0255 72.2966L94.9717 72.3438L94.9164 72.259C94.8957 72.2645 94.8702 72.2932 94.8397 72.3453C94.8245 72.3714 94.7909 72.3692 94.7388 72.3387C94.7334 72.3181 94.723 72.3208 94.7078 72.3468C94.7186 72.3881 94.7344 72.406 94.755 72.4006C94.8484 72.4202 94.926 72.4219 94.9879 72.4057ZM96.1875 71.4294L96.1793 71.3985C96.1229 71.4353 96.0664 71.4722 96.0099 71.5091C95.974 71.5405 95.9382 71.572 95.9023 71.6035L95.9104 71.6344L96.1875 71.4294ZM95.3015 71.331C95.497 71.2356 95.6567 71.1716 95.7805 71.1392C95.6459 71.1304 95.5476 71.1341 95.4857 71.1503L95.4547 71.1584C95.4558 71.2464 95.3993 71.2833 95.2853 71.2691L95.2315 71.3162L95.3015 71.331ZM95.8719 70.9829C95.8925 70.9775 95.8925 70.9775 95.8719 70.9829C95.8664 70.9622 95.8637 70.9519 95.8637 70.9519C95.8225 70.9627 95.7942 70.9812 95.779 71.0072L95.7252 71.0544C95.7665 71.0436 95.7871 71.0382 95.7871 71.0382L95.8719 70.9829ZM95.6374 70.8459C95.8634 70.6984 96.123 70.5531 96.4163 70.41L96.4082 70.379L95.6212 70.784L95.6374 70.8459ZM96.4356 70.7358L96.3965 70.7129C96.3759 70.7183 96.3504 70.7471 96.3199 70.7992L96.3509 70.7911L96.4356 70.7358ZM97.2044 70.7657C97.1783 70.7505 97.1653 70.7429 97.1653 70.7429C97.1805 70.7168 97.1751 70.6962 97.149 70.681L97.079 70.6662C97.0181 70.7704 96.9877 70.8225 96.9877 70.8225L97.1424 70.7819L97.2044 70.7657ZM98.7104 71.4624L98.6794 71.4705C98.6588 71.4759 98.6333 71.5047 98.6028 71.5568C98.6234 71.5514 98.6365 71.559 98.6419 71.5796L98.7104 71.4624ZM96.4929 70.3237C96.5136 70.3183 96.5598 70.2841 96.6315 70.2212L96.6234 70.1903L96.4929 70.3237ZM97.2191 70.6957C97.2137 70.675 97.2262 70.6387 97.2566 70.5866L97.1866 70.5719L97.1719 70.6419L97.2191 70.6957ZM96.3904 70.1852C96.4111 70.1798 96.4573 70.1456 96.529 70.0827L96.4899 70.0599L96.3904 70.1852ZM99.3208 71.8978C99.3513 71.8457 99.3768 71.8169 99.3974 71.8115C99.3974 71.8115 99.4235 71.8267 99.4756 71.8572L99.3208 71.8978ZM97.2713 70.5166C97.3028 70.5524 97.3261 70.5573 97.3414 70.5313C97.3772 70.4998 97.4055 70.4814 97.4261 70.476L97.317 70.4384L97.2241 70.4628L97.2713 70.5166ZM96.7913 69.9477C96.863 69.8848 96.9782 69.7774 97.1369 69.6255L97.1287 69.5946L96.7604 69.9558L96.7913 69.9477ZM97.417 69.6844C97.3963 69.6898 97.386 69.6925 97.386 69.6925C97.3806 69.6719 97.3779 69.6615 97.3779 69.6615L97.761 69.2302L97.7691 69.2612L97.417 69.6844ZM95.6922 71.5593C95.7487 71.5224 95.8258 71.4801 95.9236 71.4325C96.016 71.3641 96.1083 71.2958 96.2007 71.2275C96.4723 71.0018 96.682 70.7924 96.8299 70.5993L97.0516 70.3095L97.2358 70.1289L97.5179 69.691C97.6712 69.5184 97.7706 69.3931 97.8163 69.315L98.2745 68.6655L98.5338 68.2666C98.5338 68.2666 98.648 68.0713 98.8763 67.6806C98.9122 67.6491 98.9274 67.6231 98.922 67.6024C98.9166 67.5818 98.9215 67.5584 98.9367 67.5324C99.0281 67.3761 99.0737 67.298 99.0737 67.298C99.1194 67.2198 99.1574 67.1547 99.1879 67.1026C99.2129 67.0299 99.2407 66.9675 99.2711 66.9154C99.1473 66.9478 99.0783 67.0211 99.0641 67.1351C99.0641 67.1351 99.0668 67.1454 99.0722 67.166C99.0722 67.166 99.0619 67.1687 99.0412 67.1741C99.0521 67.2154 99.0172 67.3348 98.9367 67.5324L98.8063 67.6658L98.6759 67.7993L98.6678 67.7683L98.6465 67.9393L98.5993 67.8856L98.5308 68.0028C98.5362 68.0234 98.5595 68.0283 98.6008 68.0175C98.5704 68.0696 98.5421 68.088 98.5161 68.0728C98.4748 68.0836 98.4313 68.1281 98.3856 68.2063C98.3552 68.2583 98.3427 68.2947 98.3481 68.3153L98.3415 68.4163L98.2796 68.4326C98.3002 68.4271 98.3105 68.4244 98.3105 68.4244C98.3051 68.4038 98.3024 68.3935 98.3024 68.3935C98.2764 68.3783 98.2302 68.4124 98.1639 68.496C98.1182 68.5741 98.0802 68.6393 98.0497 68.6913C98.0247 68.7641 97.9943 68.8162 97.9584 68.8476C97.9225 68.8791 97.897 68.9078 97.8818 68.9339L97.7676 69.1293L97.7057 69.1455C97.5274 69.3907 97.3742 69.5633 97.246 69.6631C97.1895 69.6999 97.1308 69.7705 97.0699 69.8747L97.078 69.9056L97.3241 69.7087C97.3295 69.7294 97.3322 69.7397 97.3322 69.7397C97.3529 69.7343 97.3632 69.7316 97.3632 69.7316L96.5757 70.7652C96.4529 70.8856 96.3094 71.0115 96.1454 71.1427C95.9813 71.274 95.8096 71.4182 95.6303 71.5755C95.6564 71.5908 95.677 71.5854 95.6922 71.5593ZM97.1907 69.5783C97.2982 69.4839 97.3901 69.3716 97.4662 69.2414L97.4043 69.2576L97.5037 69.1323C97.519 69.1063 97.5369 69.0905 97.5575 69.0851C97.5934 69.0536 97.6086 69.0276 97.6032 69.007L97.7336 68.8735C97.7282 68.8529 97.7152 68.8453 97.6945 68.8507L97.6032 69.007C97.4902 69.0807 97.4185 69.1436 97.388 69.1957L97.4043 69.2576C97.3326 69.3206 97.2658 69.3601 97.2039 69.3764L97.251 69.4302L97.4124 69.2886C97.3102 69.4036 97.2363 69.5002 97.1907 69.5783ZM97.8833 69.0658C97.8681 69.0919 97.8398 69.1103 97.7986 69.1211L97.7676 69.1293L97.7595 69.0983L97.8148 69.183L97.8833 69.0658ZM98.5166 69.4621C98.5264 69.4154 98.5671 69.3606 98.6388 69.2977L98.6079 69.3058C98.5927 69.3319 98.5747 69.3476 98.5541 69.353C98.5335 69.3584 98.5183 69.3845 98.5084 69.4312L98.5166 69.4621ZM97.8752 69.0349C97.8904 69.0088 97.9083 68.9931 97.929 68.9877C97.9648 68.9562 97.9877 68.9172 97.9975 68.8705C98.0181 68.8651 98.0311 68.8727 98.0365 68.8933L97.9061 69.0268L97.8752 69.0349ZM97.931 68.4909C98.0744 68.3651 98.169 68.2631 98.2146 68.1849C98.194 68.1904 98.1837 68.1931 98.1837 68.1931C98.1783 68.1724 98.1756 68.1621 98.1756 68.1621L97.9391 68.5219L97.7712 68.7644C97.7766 68.7851 97.7896 68.7927 97.8102 68.7873L97.931 68.4909ZM99.3706 68.8081L99.3396 68.8162C99.233 68.9985 99.1798 69.0897 99.1798 69.0897L99.2107 69.0816L99.3706 68.8081ZM97.2434 70.7885C97.3053 70.7723 97.3439 70.7512 97.3591 70.7251C97.5124 70.5526 97.6499 70.3621 97.7717 70.1537C97.8586 70.0648 97.9608 69.9498 98.0781 69.8087C98.1901 69.647 98.2972 69.5086 98.3993 69.3936L98.4531 69.3464L98.4826 69.2064L98.75 68.8385L98.9245 68.495L99.3503 67.7217L99.5705 67.3L99.5999 67.1599L99.6831 66.9727L99.7648 66.6535C99.8454 66.456 99.8954 66.3105 99.915 66.2171L99.8988 66.1552L99.8369 66.1715L99.8075 66.3115L99.4452 67.2005C99.4049 67.2993 99.3543 67.4008 99.2934 67.505C99.2532 67.6038 99.2129 67.7025 99.1727 67.8013C99.1422 67.8534 99.1069 67.9289 99.0666 68.0276C99.0416 68.1004 98.9959 68.1785 98.9296 68.2621C98.9198 68.3088 98.879 68.3636 98.8073 68.4265L98.8464 68.4493C98.8572 68.4906 98.855 68.5242 98.8398 68.5503C98.7485 68.7066 98.6593 68.8292 98.5724 68.9182L98.4191 69.0907C98.4191 69.0907 98.4088 69.0934 98.3882 69.0988C98.3882 69.0988 98.3909 69.1091 98.3963 69.1298L98.4663 69.1445L98.4207 69.2226C98.3902 69.2747 98.3391 69.3322 98.2674 69.3951C98.2163 69.4527 98.1576 69.5232 98.0913 69.6067L97.7635 70.1228C97.7483 70.1488 97.5902 70.3447 97.2891 70.7104L97.2434 70.7885ZM97.9122 69.5545L98.1943 69.1166C98.1791 69.1426 98.3623 68.874 98.7439 68.3108L99.0783 67.6938C99.1141 67.6623 99.124 67.6156 99.1077 67.5537L99.2985 67.2721L99.3817 67.0848L99.4112 66.9448C99.4264 66.9187 99.4416 66.8927 99.4568 66.8667C99.4721 66.8406 99.4873 66.8146 99.5025 66.7885L99.5548 66.6094C99.545 66.6561 99.6129 66.4949 99.7588 66.1258L99.7425 66.0639L99.6887 66.1111L99.4913 66.4937C99.3912 66.7846 99.3183 66.9692 99.2726 67.0473C99.2476 67.12 99.1997 67.2318 99.129 67.3827C99.079 67.5282 99.0208 67.6427 98.9545 67.7262C98.9545 67.7262 98.7185 68.13 98.2466 68.9374L97.8503 69.5707L97.9122 69.5545ZM99.9607 68.157L99.9526 68.1261L99.6329 68.6731L99.7029 68.6878L99.9607 68.157ZM100.154 67.3786L100.1 67.4258C100.111 67.4671 100.129 67.4954 100.155 67.5106L100.154 67.3786ZM99.3087 66.8063L99.2305 66.7606L99.162 66.8778C99.1674 66.8984 99.1805 66.9061 99.2011 66.9006L99.3087 66.8063ZM99.8344 67.297L99.9404 67.0706L99.9714 67.0625L99.8653 67.2888L99.8344 67.297ZM99.0007 67.0194C99.0768 66.8891 99.1703 66.6992 99.2813 66.4495C99.2813 66.4495 99.2786 66.4392 99.2731 66.4186C99.2786 66.4392 99.2709 66.4523 99.2503 66.4577C99.1688 66.5673 99.0725 66.7469 98.9616 66.9966L98.9697 67.0275L99.0007 67.0194ZM94.6348 70.0502C94.7119 70.0079 94.8531 69.9158 95.0585 69.7737C95.0943 69.7422 95.1302 69.7108 95.166 69.6793C95.2225 69.6424 95.2714 69.6186 95.3127 69.6077C95.519 69.5536 95.7146 69.4582 95.8993 69.3216C96.0786 69.1643 96.1964 69.0672 96.2529 69.0303C96.4431 68.9143 96.5865 68.7884 96.6832 68.6528L97.1724 67.9952L97.5621 67.4629C97.5675 67.4835 97.5756 67.5145 97.5865 67.5557C97.6179 67.5916 97.6184 67.6356 97.588 67.6877C97.5782 67.7343 97.558 67.7837 97.5276 67.8358C97.5124 67.8619 97.4999 67.8982 97.49 67.9449L97.3236 68.3194C97.3855 68.3032 97.4317 68.269 97.4621 68.2169L97.5682 67.9906C97.578 67.9439 97.6008 67.9048 97.6367 67.8734C97.6932 67.8365 97.7317 67.8154 97.7524 67.8099C97.86 67.7156 97.9366 67.6293 97.9822 67.5512C98.0431 67.447 98.1067 67.3531 98.173 67.2695L98.2938 66.9732C98.3395 66.8951 98.3873 66.7833 98.4374 66.6378C98.4624 66.5651 98.5081 66.4869 98.5744 66.4034C98.6353 66.2992 98.6522 66.1955 98.6252 66.0923L98.6561 66.0842L98.7393 65.897L99.0037 65.2652C99.0734 65.0264 99.1539 64.8288 99.2452 64.6725C99.2551 64.6259 99.2622 64.5689 99.2666 64.5015C99.271 64.4342 99.3014 64.3821 99.3579 64.3453L99.3417 64.2833L99.3483 64.1824L99.3711 64.1433L99.332 64.1205C99.3212 64.0792 99.3158 64.0586 99.3158 64.0586L99.4675 63.7541L99.298 63.8647C99.3285 63.8126 99.3692 63.7578 99.4203 63.7003C99.4714 63.6428 99.4991 63.5804 99.5035 63.5131C99.4981 63.4924 99.4954 63.4821 99.4954 63.4821C99.516 63.4767 99.5264 63.474 99.5264 63.474L99.5492 63.4349L99.4792 63.4202C99.4792 63.4202 99.4689 63.4229 99.4482 63.4283C99.4482 63.4283 99.4455 63.418 99.4401 63.3974L99.432 63.3664L99.4548 63.3274C99.5428 63.3263 99.5759 63.2846 99.5543 63.202C99.5543 63.202 99.5587 63.1347 99.5675 63.0001C99.5621 62.9794 99.5593 62.9691 99.5593 62.9691L99.5659 62.8681C99.5747 62.7335 99.5781 62.5782 99.5761 62.4023C99.5774 62.0711 99.5722 61.8409 99.5604 61.7117C99.5367 61.4533 99.501 61.2752 99.4533 61.1774C99.4425 61.1361 99.4393 61.0818 99.4437 61.0145C99.4481 60.9472 99.4112 60.8907 99.333 60.845L99.3249 60.8141C99.3554 60.762 99.3576 60.7283 99.3315 60.7131C99.3055 60.6979 99.2718 60.6957 99.2305 60.7065L98.8901 60.7958L98.9586 60.6786L98.8657 60.703L98.8348 60.7111L98.2938 60.9191C98.2732 60.9245 98.2243 60.9484 98.1472 60.9907C98.0907 61.0275 98.031 61.0101 97.9681 60.9384L97.9371 60.9465C97.9111 60.9313 97.8801 60.9394 97.8443 60.9709C97.803 60.9817 97.759 60.9822 97.7123 60.9724C97.5679 61.0103 97.4522 61.0737 97.3652 61.1627L97.1501 61.3514L97.282 61.3499C97.1027 61.5072 96.9979 61.6119 96.9674 61.664L96.9136 61.7112C96.8483 61.8827 96.7902 61.9972 96.7391 62.0547L96.594 62.2582L96.3169 62.4632L96.3641 62.517L96.6264 62.382C96.596 62.4341 96.5704 62.4629 96.5498 62.4683C96.4933 62.5051 96.4086 62.5605 96.2956 62.6342C96.1978 62.6819 96.1234 62.7345 96.0723 62.792C96.0571 62.8181 95.9854 62.881 95.8572 62.9808C95.7442 63.0545 95.6757 63.1717 95.6517 63.3324L95.5669 63.3877C95.5257 63.3986 95.4996 63.3833 95.4888 63.3421C95.4671 63.2595 95.4406 63.2003 95.4091 63.1645C95.4091 63.1645 95.3988 63.1672 95.3782 63.1726C95.3782 63.1726 95.3755 63.1623 95.37 63.1416C95.2875 63.1633 95.2131 63.2159 95.1468 63.2994C95.1011 63.3776 95.0707 63.4297 95.0554 63.4557C95.025 63.5078 94.9994 63.5366 94.9788 63.542C94.9582 63.5474 94.9403 63.5631 94.925 63.5892C94.9098 63.6152 94.9049 63.6386 94.9103 63.6592C94.8907 63.7526 94.8711 63.8459 94.8514 63.9393C94.8264 64.012 94.8041 64.0951 94.7845 64.1884C94.5686 65.2155 94.4438 65.8327 94.41 66.04C94.3707 66.2268 94.3139 66.6828 94.2395 67.4081C94.2405 67.496 94.2339 67.597 94.2197 67.711C94.2055 67.825 94.1935 67.9053 94.1837 67.952L94.1979 68.5107L94.3303 69.8985C94.3465 69.9604 94.3834 70.0169 94.4409 70.068C94.5136 70.093 94.5783 70.0871 94.6348 70.0502ZM100.213 67.8592C100.279 67.6877 100.347 67.5265 100.417 67.3756C100.503 67.1987 100.579 67.0245 100.644 66.853L100.613 66.8611C100.558 66.9859 100.487 67.1368 100.401 67.3137C100.33 67.4646 100.255 67.6388 100.174 67.8363L100.213 67.8592ZM100.271 67.4472C100.332 67.343 100.38 67.2751 100.416 67.2437C100.395 67.2491 100.382 67.2415 100.377 67.2208C100.32 67.2577 100.285 67.3331 100.271 67.4472ZM99.4294 66.5099C99.4034 66.4947 99.38 66.4898 99.3594 66.4952C99.354 66.4746 99.3513 66.4643 99.3513 66.4643C99.3513 66.4643 99.3361 66.4903 99.3056 66.5424C99.3164 66.5837 99.3425 66.5989 99.3838 66.5881L99.4294 66.5099ZM98.6109 69.5697L98.6647 69.5225L99.1148 68.8421L99.1214 68.7411L99.198 68.6548C99.2133 68.6288 99.2106 68.6185 99.1899 68.6239L99.2437 68.5767L99.2422 68.4447L99.2747 68.5686C99.2997 68.4958 99.335 68.4204 99.3807 68.3422C99.4264 68.2641 99.4411 68.1941 99.4249 68.1322C99.4661 68.1213 99.502 68.0899 99.5324 68.0378C99.6041 67.9749 99.6803 67.8446 99.7608 67.6471C99.801 67.5483 99.8489 67.4365 99.9044 67.3117C99.9599 67.1868 100.013 67.0517 100.063 66.9062C100.108 66.8281 100.098 66.7868 100.03 66.7824L100.053 66.7433L100.301 66.0497C100.39 65.7175 100.45 65.5254 100.481 65.4733L100.512 65.4651C100.507 65.5325 100.482 65.6052 100.437 65.6833C100.53 65.703 100.587 65.6661 100.606 65.5727C100.641 65.4533 100.666 65.3366 100.68 65.2226C100.689 65.088 100.71 64.9609 100.745 64.8415C100.764 64.6602 100.778 64.5462 100.788 64.4995C100.782 64.4789 100.795 64.4425 100.825 64.3904L100.839 64.1885C100.867 63.9605 100.86 63.8079 100.818 63.7308C100.812 63.7101 100.82 63.6971 100.841 63.6917C100.885 63.5256 100.879 63.417 100.821 63.3659C100.841 63.2726 100.845 63.2052 100.835 63.164L100.725 63.1264L100.688 63.2355C100.716 63.4267 100.724 63.6672 100.712 63.9571L100.681 63.9652L100.679 63.8333C100.649 63.8854 100.623 63.9141 100.603 63.9195L100.631 63.6475C100.64 63.6009 100.632 63.5259 100.605 63.4228C100.512 63.4911 100.469 63.5356 100.474 63.5562L100.363 64.0154C100.371 64.212 100.368 64.4112 100.354 64.6132L100.379 64.706L100.462 64.5188L100.486 64.6117L100.532 64.5335C100.543 64.5748 100.541 64.6084 100.525 64.6345L100.489 64.8755C100.464 64.9482 100.439 65.021 100.414 65.0937C100.41 65.161 100.395 65.2311 100.37 65.3038C100.351 65.3972 100.31 65.4959 100.249 65.6001C99.9835 66.7726 99.551 67.8565 98.9519 68.8517C98.978 68.8669 99.0116 68.8691 99.0529 68.8583L98.9991 68.9055L98.9682 68.9136C98.9269 68.9244 98.8834 68.9689 98.8378 69.0471C98.7867 69.1046 98.7666 69.154 98.7774 69.1952L98.7855 69.2262L98.8017 69.2881L98.7398 69.3043L98.7236 69.2424L98.6094 69.4378L98.6794 69.4525L98.6257 69.4997L98.6109 69.5697L98.5328 69.524L98.4496 69.7113L98.4805 69.7032C98.5012 69.6977 98.5115 69.695 98.5115 69.695C98.5267 69.669 98.5446 69.6533 98.5653 69.6478L98.5506 69.7179L98.5815 69.7098L98.6109 69.5697ZM99.4309 68.6599L99.6217 68.3783C99.637 68.3522 99.6571 68.3028 99.6821 68.2301C99.7224 68.1313 99.7735 68.0738 99.8354 68.0576C99.856 68.0522 99.8636 68.0391 99.8582 68.0185C99.8734 67.9925 99.8914 67.9767 99.912 67.9713L99.9039 67.9404L99.8191 67.9957C99.8191 67.9957 99.8088 67.9984 99.7882 68.0038C99.7882 68.0038 99.7855 67.9935 99.7801 67.9728C99.8311 67.9153 99.91 67.7954 100.017 67.6131L100.025 67.644L99.8957 67.9094L99.9658 67.9241L100.155 67.5106C100.15 67.4899 100.144 67.4693 100.139 67.4487C100.149 67.402 100.169 67.3526 100.199 67.3005C100.199 67.3005 100.26 67.1963 100.382 66.9879C100.457 66.7697 100.495 66.6606 100.495 66.6606L100.69 66.1461L100.743 65.967L100.627 66.0304L100.769 65.5631L100.847 65.6088C100.927 65.3232 100.991 65.0638 101.04 64.8304C101.089 64.5969 101.133 64.3869 101.172 64.2001C101.167 64.1795 101.154 64.1719 101.133 64.1773C101.144 64.2186 101.129 64.2446 101.088 64.2554L101.086 64.1235L101.218 64.122L101.124 64.0144L101.132 64.0454L101.083 63.8597C101.068 63.8857 101.053 63.9118 101.037 63.9378C101.037 63.9378 101.04 63.9481 101.046 63.9688L100.913 64.599L100.647 65.7275L100.625 65.8985L100.474 66.2029L100.165 67.0448C100.125 67.1435 100.082 67.232 100.036 67.3101C99.9906 67.3883 99.9553 67.4637 99.9303 67.5365L99.5745 68.3245L99.4 68.668L99.4309 68.6599ZM100.092 66.7662C100.133 66.7554 100.151 66.7396 100.146 66.719L100.454 65.8772L100.471 65.9391L100.531 65.7909L100.546 65.7209L100.453 65.7452L100.399 65.7924L100.384 65.8625C100.355 66.0025 100.265 66.2907 100.115 66.7271C100.115 66.7271 100.118 66.7374 100.123 66.7581C100.123 66.7581 100.113 66.7608 100.092 66.7662ZM96.0353 64.2904C95.9899 63.9494 95.9663 63.691 95.9642 63.5151C95.9686 63.4478 95.9991 63.3957 96.0556 63.3588L96.1926 63.1244C96.1012 63.2807 96.0566 63.4468 96.0586 63.6227C96.0813 63.7932 96.0931 63.9224 96.0941 64.0103C96.0853 64.145 96.0891 64.2432 96.1053 64.3052L96.0515 64.3523L96.0353 64.2904ZM95.1843 63.1903C95.205 63.1849 95.2126 63.1719 95.2072 63.1513L95.1062 63.1447C95.1062 63.1447 95.0959 63.1474 95.0752 63.1528C95.0752 63.1528 95.0779 63.1631 95.0833 63.1837C95.1094 63.199 95.1431 63.2012 95.1843 63.1903ZM95.2579 62.8402C95.2579 62.8402 95.2476 62.8429 95.2269 62.8483C95.2269 62.8483 95.2242 62.838 95.2188 62.8174L95.129 63.1056L95.199 63.1203L95.2579 62.8402ZM99.8293 65.5118L99.7902 65.489C99.7706 65.5824 99.7635 65.6394 99.7689 65.66L99.8293 65.5118ZM99.5933 65.2429L99.5624 65.251L99.4482 65.4464C99.4536 65.467 99.4563 65.4773 99.4563 65.4773C99.477 65.4719 99.4873 65.4692 99.4873 65.4692L99.5933 65.2429ZM99.4771 65.935L99.5553 65.9807L99.539 65.9188C99.5695 65.8667 99.5847 65.8406 99.5847 65.8406L99.6598 65.6224L99.7481 65.2023C99.8276 64.9168 99.8723 64.7507 99.8821 64.704L99.3777 66.0604C99.3831 66.081 99.3858 66.0913 99.3858 66.0913C99.4064 66.0859 99.4167 66.0832 99.4167 66.0832L99.4771 65.935ZM100.118 65.6016C100.112 65.581 100.099 65.5734 100.078 65.5788L100.018 65.727L100.049 65.7189L100.118 65.6016ZM95.3492 62.6839C95.3492 62.6839 95.3438 62.6633 95.333 62.622L95.2792 62.6692C95.2846 62.6898 95.2721 62.7262 95.2417 62.7783C95.2623 62.7729 95.2753 62.7805 95.2807 62.8011L95.3492 62.6839ZM94.7698 62.2404L94.8007 62.2323L94.7307 62.2176L94.5155 62.4064L94.5546 62.4292L94.7698 62.2404ZM100.774 65.9589C100.799 65.8861 100.806 65.8291 100.795 65.7879C100.784 65.7466 100.786 65.7129 100.802 65.6869L100.793 65.6559L100.762 65.6641C100.779 65.726 100.782 65.7803 100.772 65.8269C100.757 65.853 100.744 65.8894 100.735 65.936C100.755 65.9306 100.768 65.9382 100.774 65.9589ZM101.21 66.1091C101.225 66.083 101.24 66.057 101.256 66.0309C101.271 66.0049 101.276 65.9815 101.27 65.9609L101.3 65.8209C101.3 65.8209 101.289 65.8236 101.269 65.829C101.269 65.829 101.266 65.8187 101.261 65.798L101.171 66.0862C101.192 66.0808 101.205 66.0884 101.21 66.1091ZM100.636 66.822C100.748 66.6603 100.812 66.5664 100.827 66.5404L100.887 66.3922L100.918 66.3841C100.932 66.2701 100.985 66.091 101.075 65.8467C101.09 65.8207 101.092 65.787 101.082 65.7458L101.118 65.5047C101.112 65.4841 101.112 65.4841 101.118 65.5047C101.138 65.4993 101.146 65.4863 101.14 65.4657L101.225 65.4103C101.22 65.3897 101.212 65.3588 101.201 65.3175C101.205 65.2502 101.22 65.1801 101.245 65.1074L101.296 64.7964L101.366 64.8111C101.386 64.8057 101.412 64.7769 101.442 64.7248C101.37 64.6998 101.333 64.6873 101.333 64.6873C101.333 64.6873 101.331 64.6769 101.325 64.6563C101.34 64.6303 101.345 64.6069 101.34 64.5863L101.278 64.6025L101.296 64.7964L101.211 64.8517C101.196 64.8777 101.194 64.9114 101.204 64.9527C101.21 64.9733 101.205 64.9966 101.19 65.0227C101.181 65.1573 101.164 65.261 101.139 65.3337C100.973 65.7082 100.86 66.0355 100.801 66.3156L100.628 66.7911L100.636 66.822ZM95.5953 62.487C95.5899 62.4664 95.5872 62.4561 95.5872 62.4561C95.6079 62.4507 95.6182 62.448 95.6182 62.448L95.6933 62.2298L95.6852 62.1988C95.6243 62.303 95.5889 62.3785 95.5791 62.4251C95.5791 62.4251 95.5845 62.4458 95.5953 62.487ZM100.015 65.4631C99.9944 65.4685 99.9841 65.4712 99.9841 65.4712C99.9786 65.4506 99.9759 65.4403 99.9759 65.4403L100.007 65.4322L100.08 65.082L100.208 64.6847L100.192 64.6228C100.207 64.5968 100.206 64.5528 100.19 64.4909L100.234 64.2808C100.204 64.3329 100.164 64.4317 100.113 64.5772C100.119 64.5978 100.101 64.6135 100.06 64.6243L99.9896 64.6096C100.052 64.5934 100.08 64.575 100.074 64.5543C100.09 64.5283 100.092 64.4946 100.081 64.4533L100.004 64.5396L99.9896 64.6096L99.88 65.2008L99.9272 65.2546L99.9582 65.2464C99.969 65.2877 99.9668 65.3214 99.9516 65.3474L99.8912 65.4956L99.9303 65.5184L100.015 65.4631ZM101.261 65.798C101.384 65.6776 101.418 65.5582 101.365 65.4398C101.34 65.5125 101.323 65.5722 101.313 65.6189C101.303 65.6656 101.286 65.7253 101.261 65.798ZM95.1234 61.9492C95.0713 61.9187 95.0453 61.9035 95.0453 61.9035L94.9996 61.9816C94.9996 61.9816 95.0023 61.992 95.0077 62.0126C95.0077 62.0126 95.0181 62.0099 95.0387 62.0045L95.1234 61.9492ZM101.112 64.977L101.059 65.1561C101.08 65.1507 101.093 65.1583 101.098 65.179L101.112 64.977ZM95.3127 61.5356C95.2508 61.5519 95.2019 61.5757 95.1661 61.6072L95.2051 61.63L95.3127 61.5356ZM95.5131 61.4169L95.505 61.3859L95.3746 61.5194L95.5131 61.4169ZM101.208 64.5878L101.169 64.565L101.117 64.7441L101.179 64.7279L101.208 64.5878ZM95.3548 61.8223C95.4069 61.8528 95.4406 61.855 95.4558 61.8289C95.471 61.8029 95.4862 61.7768 95.5015 61.7508C95.5427 61.7399 95.571 61.7215 95.5862 61.6955C95.6014 61.6694 95.609 61.6564 95.609 61.6564C95.6611 61.6868 95.6948 61.689 95.71 61.663C95.7198 61.6163 95.7323 61.5799 95.7476 61.5539L95.808 61.4057L95.878 61.4204C95.8726 61.3998 95.8699 61.3895 95.8699 61.3895C95.8905 61.3841 95.9008 61.3814 95.9008 61.3814C96.0138 61.3076 96.0703 61.2708 96.0703 61.2708C96.1268 61.2339 96.1626 61.2024 96.1779 61.1764C96.2083 61.1243 96.2312 61.0852 96.2464 61.0592L96.3149 60.9419L96.3068 60.911L96.2758 60.9191C96.2193 60.956 96.1655 61.0032 96.1144 61.0607C96.084 61.1128 96.0405 61.1573 95.984 61.1941C95.9221 61.2104 95.876 61.2445 95.8455 61.2966C95.8249 61.302 95.8042 61.3075 95.7836 61.3129C95.7782 61.2922 95.7679 61.2949 95.7526 61.321L95.6451 61.4154L95.5913 61.4626L95.3909 61.5813C95.3702 61.5867 95.342 61.6051 95.3061 61.6366C95.2703 61.6681 95.2784 61.699 95.3305 61.7295L95.13 61.8482L95.1382 61.8791C95.1794 61.8683 95.2207 61.8575 95.262 61.8467C95.2978 61.8152 95.3288 61.8071 95.3548 61.8223ZM101.433 64.5619L101.447 64.4919L101.316 64.4934C101.316 64.4934 101.318 64.5037 101.324 64.5244C101.324 64.5244 101.313 64.5271 101.293 64.5325L101.332 64.5553C101.384 64.5858 101.42 64.5983 101.441 64.5929L101.433 64.5619ZM99.9998 64.1438C100.051 64.0863 100.101 63.9848 100.152 63.8394C100.181 63.6993 100.19 63.6086 100.179 63.5674C100.184 63.5001 100.144 63.4332 100.061 63.3669L99.9967 63.8799L99.946 64.191L99.9998 64.1438ZM99.9105 63.8033C99.9409 63.7512 99.9561 63.7252 99.9561 63.7252L99.8927 63.6095C99.9394 63.6193 99.96 63.6139 99.9546 63.5933C99.9699 63.5672 99.9851 63.5412 100 63.5151C99.9797 63.5205 99.9693 63.5232 99.9693 63.5232C99.9639 63.5026 99.9612 63.4923 99.9612 63.4923C99.9308 63.5444 99.9052 63.5731 99.8846 63.5785L99.8927 63.6095C99.8775 63.6355 99.878 63.6795 99.8942 63.7414L99.9105 63.8033ZM100.604 64.0515L100.65 63.9733L100.744 64.0809L100.721 64.12L100.604 64.0515ZM100.365 63.5187C100.396 63.4666 100.415 63.3732 100.424 63.2386C100.368 63.2754 100.322 63.3536 100.287 63.473L100.334 63.5268L100.365 63.5187ZM101.423 64.3991C101.474 64.3415 101.453 64.303 101.36 64.2834L101.422 64.2671C101.463 64.2563 101.486 64.2612 101.492 64.2818L101.49 64.1499L101.443 64.0961C101.437 64.0755 101.455 64.0598 101.497 64.0489C101.517 64.0435 101.525 64.0305 101.52 64.0099C101.535 63.9838 101.534 63.9398 101.518 63.8779C101.507 63.8367 101.489 63.8084 101.463 63.7932C101.587 63.7607 101.585 63.6728 101.46 63.5293L101.463 63.7932L101.412 64.1042L101.443 64.0961C101.423 64.1895 101.396 64.2519 101.36 64.2834C101.386 64.2986 101.407 64.3371 101.423 64.3991ZM101.281 63.4771L101.25 63.4852L101.147 63.9753L101.217 63.9901L101.281 63.4771ZM99.4213 62.4429C99.3584 62.3712 99.3449 62.3196 99.3807 62.2882C99.4112 62.2361 99.434 62.197 99.4492 62.1709L99.4213 62.4429ZM101.272 63.4461C101.281 63.3115 101.293 63.1871 101.307 63.0731C101.235 63.1361 101.202 63.1778 101.207 63.1985L101.24 63.3223C101.251 63.3636 101.249 63.3972 101.233 63.4233C101.254 63.4179 101.267 63.4255 101.272 63.4461ZM101.598 63.4268L101.611 63.2249L101.592 62.8991L101.561 62.9072L101.491 63.5212L101.53 63.544L101.598 63.4268ZM101.04 62.8123C101.019 62.8177 101.006 62.8101 101.001 62.7895L100.941 62.9377C100.961 62.9323 100.974 62.9399 100.98 62.9605L101.04 62.8123ZM100.84 62.9311C100.84 62.9311 100.842 62.9414 100.848 62.962C100.848 62.962 100.858 62.9593 100.879 62.9539L100.893 62.8839L100.753 62.8544L100.807 62.8073L100.838 62.7991L100.9 62.7829C100.859 62.7937 100.833 62.7785 100.822 62.7372C100.811 62.696 100.815 62.6286 100.835 62.5353L100.741 62.4277C100.72 62.4331 100.702 62.4488 100.687 62.4749C100.672 62.5009 100.667 62.5243 100.672 62.5449L100.683 62.8397L100.763 63.0173L100.84 62.9311ZM97.2029 60.5436C97.2648 60.5274 97.3213 60.4905 97.3724 60.433C97.4234 60.3755 97.4512 60.3131 97.4556 60.2458C97.3991 60.2826 97.335 60.3325 97.2633 60.3954C97.2122 60.453 97.1584 60.5001 97.1019 60.537L97.2029 60.5436ZM96.0505 59.5557L96.0424 59.5247L96.0033 59.5019L95.881 59.6663L95.8892 59.6972L96.0505 59.5557ZM100.848 62.3333C100.843 62.3127 100.85 62.2997 100.871 62.2942L100.731 62.2648L100.692 62.242L100.721 62.1019C100.721 62.1019 100.716 62.0813 100.705 62.04L100.659 62.1182L100.669 62.2811C100.68 62.3223 100.678 62.356 100.662 62.382L100.809 62.3105L100.848 62.3333ZM96.2738 59.3978L96.1337 59.3684C96.1131 59.3738 96.0876 59.4026 96.0571 59.4547C96.1092 59.4851 96.1353 59.5003 96.1353 59.5003L96.2738 59.3978ZM101.211 62.8336L101.25 62.8565L101.266 62.9184L101.297 62.9103C101.281 62.8484 101.283 62.7707 101.302 62.6774L101.271 62.6855C101.271 62.6855 101.264 62.6985 101.249 62.7245C101.254 62.7452 101.259 62.7658 101.265 62.7865C101.259 62.7658 101.246 62.7582 101.226 62.7636C101.203 62.5931 101.183 62.389 101.164 62.1512C101.167 61.9079 101.136 61.7065 101.072 61.5468L101.167 63.0437L101.206 63.0666L101.211 62.8336ZM100.705 62.04C100.7 62.0194 100.694 61.9988 100.689 61.9781C100.704 61.9521 100.712 61.939 100.712 61.939C100.686 61.9238 100.652 61.9216 100.611 61.9325L100.705 62.04ZM101.581 62.6043L101.557 62.5114C101.53 62.4083 101.518 62.323 101.523 62.2557L101.492 62.2638L101.55 62.6124L101.589 62.6352L101.581 62.6043ZM101.433 62.5439C101.431 62.368 101.419 62.2388 101.397 62.1562L101.366 62.1643L101.371 62.5601L101.41 62.583L101.433 62.5439ZM97.653 59.8632L97.5601 59.8875L97.5373 59.9266C97.5992 59.9103 97.6328 59.9125 97.6382 59.9332L97.653 59.8632ZM99.7172 61.1744L99.6603 60.9577L99.6294 60.9658L99.5984 60.9739L99.6147 61.0358C99.6309 61.0977 99.652 61.1363 99.6781 61.1515L99.6943 61.2134L99.7172 61.1744ZM101.511 61.9609L101.487 61.868L101.456 61.8761L101.45 61.9771L101.497 62.0309L101.511 61.9609ZM96.2966 59.3588C96.3683 59.2959 96.4194 59.2383 96.4499 59.1862C96.4857 59.1548 96.5216 59.1233 96.5574 59.0919C96.5933 59.0604 96.6422 59.0366 96.7041 59.0203C96.7247 59.0149 96.7557 59.0068 96.7969 58.996C96.8328 58.9645 96.8453 58.9281 96.8345 58.8869L96.8949 58.7387C96.9155 58.7333 96.9231 58.7203 96.9177 58.6996C96.9383 58.6942 96.9487 58.6915 96.9487 58.6915C96.9432 58.6709 96.9405 58.6606 96.9405 58.6606L96.9096 58.6687C96.8737 58.7001 96.8276 58.7343 96.7711 58.7712C96.7298 58.782 96.707 58.8211 96.7026 58.8884C96.6982 58.9557 96.6291 59.0289 96.4955 59.1081L96.1875 59.3212C96.2396 59.3517 96.276 59.3642 96.2966 59.3588ZM100.588 61.3428C100.572 61.2809 100.574 61.2473 100.595 61.2418L100.579 61.1799C100.573 61.1593 100.56 61.1517 100.54 61.1571L100.502 61.2662C100.508 61.2868 100.536 61.3124 100.588 61.3428ZM101.479 61.8371C101.5 61.8316 101.507 61.8186 101.502 61.798L101.468 61.5422C101.427 61.5531 101.406 61.6025 101.407 61.6904C101.403 61.7577 101.417 61.8093 101.448 61.8452L101.479 61.8371ZM98.0163 59.7348C98.0261 59.6881 98.0202 59.6235 97.9985 59.5409L97.9676 59.5491L97.9544 59.751L98.0163 59.7348ZM97.7118 59.5831C97.7118 59.5831 97.7325 59.5776 97.7737 59.5668L97.8585 59.5115C97.8737 59.4855 97.9019 59.467 97.9432 59.4562L97.927 59.3943L97.6956 59.5212L97.7037 59.5521C97.6885 59.5782 97.6809 59.5912 97.6809 59.5912C97.7015 59.5858 97.7118 59.5831 97.7118 59.5831ZM101.062 62.0126C101.038 61.7542 101.025 61.537 101.023 61.3611L101.064 61.5159L101.095 61.5077L101.059 61.1201C101.018 61.1309 100.99 61.1493 100.975 61.1754L100.966 61.1444C101.044 61.1021 101.048 61.0348 100.98 60.9425C100.974 60.9218 100.958 60.9039 100.932 60.8887C100.906 60.8735 100.88 60.8582 100.854 60.843C100.833 60.7605 100.806 60.7013 100.775 60.6654L101.031 62.0207L101.062 62.0126ZM97.5637 59.5227C97.5789 59.4966 97.6403 59.4364 97.7479 59.342C97.7631 59.316 97.8043 59.3052 97.8717 59.3096C97.9542 59.2879 98.0107 59.251 98.0411 59.1989C98.165 59.1665 98.1851 59.1171 98.1015 59.0508C98.0809 59.0562 98.0499 59.0643 98.0087 59.0751C97.9826 59.0599 97.962 59.0653 97.9468 59.0914C97.6589 59.2551 97.4764 59.3581 97.3993 59.4004L97.3683 59.4085L97.3764 59.4395C97.4025 59.4547 97.4258 59.4596 97.4464 59.4542C97.4877 59.4433 97.5111 59.4483 97.5165 59.4689L97.5083 59.4379C97.4931 59.464 97.4909 59.4976 97.5018 59.5389L97.5637 59.5227ZM100.501 61.1343C100.531 61.0822 100.546 61.0561 100.546 61.0561C100.556 61.0094 100.545 60.9682 100.514 60.9323C100.503 60.891 100.502 60.8471 100.512 60.8004C100.501 60.7591 100.478 60.7102 100.441 60.6537C100.398 60.5766 100.393 60.512 100.423 60.4599L100.298 60.3604L100.267 60.3686C100.18 60.4575 100.188 60.5325 100.293 60.5934L100.403 60.7628L100.388 60.8329L100.453 61.0805L100.501 61.1343ZM97.2891 58.6022L97.2729 58.5403L96.9877 58.7143L97.0349 58.7681L97.2891 58.6022ZM98.8373 59.5856C98.9763 59.5271 99.1072 59.4376 99.23 59.3172L99.0981 59.3187L99.1128 59.2487L98.9809 59.2502C98.9809 59.2502 98.9679 59.2426 98.9418 59.2274C98.9364 59.2067 98.9234 59.1991 98.9028 59.2045C98.8821 59.2099 98.8305 59.2235 98.748 59.2451C98.6654 59.2668 98.609 59.3036 98.5785 59.3557C98.5569 59.2732 98.5048 59.2427 98.4222 59.2644C98.3603 59.2806 98.306 59.2839 98.2593 59.274L98.375 59.2106C98.3023 59.1856 98.2274 59.1942 98.1502 59.2365C98.0677 59.2581 98.0112 59.295 97.9808 59.3471C97.9916 59.3884 98.0073 59.4063 98.028 59.4009L98.1518 59.3684C98.1778 59.3836 98.2218 59.3831 98.2837 59.3669L98.2933 59.5298L98.1518 59.3684L98.1076 59.5785C98.113 59.5991 98.1005 59.6355 98.0701 59.6876L98.0782 59.7185L98.132 59.6714C98.2101 59.717 98.2671 59.7241 98.303 59.6927C98.4887 59.644 98.6201 59.5985 98.6972 59.5562L98.8292 59.5546L98.8373 59.5856ZM98.5836 59.1228L98.4907 59.1472L98.6079 59.2157L98.5836 59.1228ZM101.219 60.8466C101.24 60.8412 101.247 60.8281 101.242 60.8075L101.162 60.6299L101.131 60.638L101.219 60.8466ZM97.382 58.5778C97.4439 58.5616 97.4901 58.5274 97.5205 58.4753L97.5124 58.4444L97.382 58.5778ZM97.418 58.3368L97.348 58.3221L97.3267 58.4931L97.3658 58.5159L97.418 58.3368ZM100.614 60.1783L100.495 59.9778C100.5 59.9985 100.493 60.0115 100.472 60.0169L100.552 60.1945L100.614 60.1783ZM106.766 72.7569C106.714 72.7264 106.621 72.7068 106.486 72.698C106.476 72.7447 106.446 72.7528 106.393 72.7224C106.238 72.719 106.139 72.6787 106.097 72.6016L105.956 72.4402L105.861 72.3327L105.845 72.2708C105.834 72.2295 105.816 72.2012 105.79 72.186L105.759 72.1941C105.753 72.1735 105.719 72.1273 105.656 72.0556C105.651 72.035 105.632 72.0067 105.601 71.9709C105.595 71.9502 105.595 71.9063 105.599 71.8389C105.615 71.8129 105.588 71.7537 105.52 71.6613C105.488 71.6255 105.457 71.6336 105.427 71.6857L105.435 71.7166C105.414 71.7221 105.401 71.7145 105.396 71.6938C105.363 71.57 105.329 71.4799 105.292 71.4234C105.286 71.4027 105.258 71.3772 105.206 71.3467L105.189 71.2848L105.228 71.3077L105.259 71.2995C105.243 71.2376 105.225 71.2094 105.204 71.2148C105.183 71.2202 105.17 71.2126 105.165 71.192C105.149 71.1301 105.148 71.0861 105.163 71.06C105.158 71.0394 105.15 71.0085 105.139 70.9672L105.131 70.9362L105.108 70.9753L105.124 71.0372L105.093 71.0453C105.067 71.0301 105.046 70.9915 105.03 70.9296C104.999 70.8938 104.99 70.8628 105.006 70.8368C105 70.8161 104.995 70.7955 104.989 70.7749L105.02 70.7667C105.051 70.7147 105.063 70.6783 105.058 70.6577C105.052 70.637 105.024 70.6115 104.972 70.581C104.94 70.5452 104.914 70.486 104.892 70.4034C104.87 70.3209 104.867 70.2226 104.881 70.1086C104.874 70 104.866 69.9251 104.855 69.8838C104.865 69.8371 104.872 69.7801 104.876 69.7128C104.881 69.6455 104.895 69.5755 104.92 69.5028C104.929 69.3681 104.931 69.2905 104.925 69.2698L104.917 69.2389C104.917 69.2389 104.907 69.2416 104.886 69.247C104.886 69.247 104.889 69.2573 104.895 69.278L104.858 69.519C104.839 69.6124 104.834 69.6797 104.845 69.7209L104.792 69.7681L104.775 69.7062C104.764 69.665 104.769 69.5976 104.788 69.5043C104.772 69.4424 104.774 69.3647 104.794 69.2714C104.793 69.1834 104.794 69.1058 104.799 69.0385C104.803 68.9711 104.807 68.9038 104.812 68.8365L104.832 68.5336C104.852 68.5282 104.852 68.5282 104.832 68.5336C104.826 68.5129 104.823 68.5026 104.823 68.5026L104.807 68.4407C104.796 68.3994 104.801 68.3321 104.82 68.2388L104.812 68.2078L104.781 68.2159L104.767 68.2859L104.744 68.325L104.736 68.2941C104.736 68.2941 104.725 68.2968 104.705 68.3022C104.705 68.3022 104.702 68.2919 104.697 68.2712L104.705 68.3022L104.661 68.5123L104.638 68.5513L104.63 68.5204C104.608 68.4378 104.602 68.3732 104.612 68.3265C104.596 68.2646 104.595 68.2207 104.61 68.1946C104.62 68.1479 104.63 68.1012 104.64 68.0546L104.591 67.8688L104.56 67.877C104.539 67.8824 104.532 67.8954 104.537 67.916L104.484 67.9632C104.484 67.9632 104.473 67.9659 104.453 67.9713C104.447 67.9507 104.455 67.9377 104.475 67.9323C104.454 67.8497 104.461 67.7927 104.497 67.7613L104.489 67.7303C104.488 67.6424 104.494 67.5414 104.508 67.4274C104.523 67.3134 104.535 67.233 104.544 67.1864C104.564 67.093 104.568 67.0257 104.558 66.9844C104.573 66.9583 104.57 66.948 104.549 66.9534C104.544 66.9328 104.539 66.9122 104.533 66.8915C104.492 66.9024 104.474 66.9181 104.479 66.9387C104.479 66.9387 104.464 66.9648 104.434 67.0169L104.409 66.924L104.439 66.784L104.431 66.753L104.4 66.7611C104.411 66.8024 104.401 66.8491 104.37 66.9012L104.378 66.9321C104.373 66.9115 104.36 66.9039 104.339 66.9093L104.338 66.7774L104.33 66.7464C104.309 66.7518 104.302 66.7648 104.307 66.7855C104.276 66.8376 104.269 66.8946 104.286 66.9565C104.265 66.9619 104.257 66.9749 104.263 66.9956L104.325 66.9793C104.325 66.9793 104.327 66.9896 104.333 67.0103C104.333 67.0103 104.343 67.0076 104.364 67.0022C104.343 67.0076 104.336 67.0206 104.341 67.0412C104.274 67.0368 104.251 67.0759 104.272 67.1584L104.13 67.6258L104.122 67.5948L104.15 67.3228C104.184 67.1155 104.207 66.9108 104.221 66.7089L104.293 66.2268L104.307 66.1568C104.266 66.1676 104.248 66.1833 104.254 66.204L104.21 66.414L104.195 66.4841C104.184 66.4428 104.189 66.4195 104.21 66.414L104.318 65.691C104.372 65.4782 104.428 65.1438 104.485 64.6878L104.579 64.1667C104.603 64.006 104.635 63.8323 104.674 63.6455C104.708 63.4382 104.729 63.2232 104.737 63.0006C104.725 62.8714 104.729 62.7601 104.748 62.6667C104.768 62.5733 104.78 62.493 104.784 62.4257C104.832 62.1043 104.858 61.866 104.862 61.7107L104.937 60.8638L105.008 60.2498C105.025 59.9806 105.028 59.7813 105.016 59.6521L105.069 59.473C105.111 59.131 105.134 58.8384 105.136 58.5951C105.135 58.5072 105.154 58.3698 105.193 58.1831L105.173 57.0967L105.268 56.5756L105.288 56.2726L105.332 56.0626L105.378 55.9844C105.361 55.9225 105.358 55.8243 105.366 55.6896L105.479 55.3623C105.494 55.3363 105.497 55.3026 105.486 55.2614C105.516 55.2093 105.542 55.1805 105.562 55.1751C105.624 55.1589 105.691 55.1193 105.763 55.0564L105.755 55.0254C105.759 54.9581 105.748 54.8728 105.721 54.7697C105.704 54.7078 105.742 54.6426 105.835 54.5743C105.876 54.5635 105.904 54.545 105.92 54.519C105.935 54.4929 105.95 54.4669 105.965 54.4408C105.96 54.4202 105.972 54.3838 106.003 54.3317C105.997 54.3111 106.005 54.2981 106.026 54.2927L106.001 54.1998L106.055 54.1526L106.032 54.1917L106.079 54.2455C106.1 54.2401 106.11 54.2374 106.11 54.2374C106.105 54.2167 106.102 54.2064 106.102 54.2064C106.144 54.1956 106.167 54.2005 106.172 54.2211L106.203 54.213L106.234 54.2049L106.242 54.2358L106.19 54.415L106.214 54.5078L106.229 54.4378C106.224 54.4172 106.267 54.3727 106.36 54.3044C106.38 54.2989 106.421 54.2881 106.483 54.2719C106.56 54.2296 106.612 54.1721 106.637 54.0994L106.659 54.0603L106.707 54.1141C106.717 54.1553 106.736 54.1836 106.762 54.1988C106.792 54.1467 106.808 54.1207 106.808 54.1207C106.823 54.0946 106.868 53.9725 106.943 53.7543C107.015 53.6914 107.056 53.6366 107.065 53.5899C107.065 53.5899 107.076 53.5872 107.096 53.5818C107.117 53.5764 107.13 53.584 107.135 53.6046C107.172 53.6611 107.227 53.6579 107.298 53.595C107.293 53.5743 107.3 53.5613 107.321 53.5559L107.306 53.6259C107.312 53.6466 107.307 53.6699 107.292 53.696C107.276 53.722 107.282 53.7426 107.308 53.7579C107.334 53.7731 107.378 53.7726 107.44 53.7563C107.522 53.7347 107.542 53.6853 107.5 53.6082C107.489 53.5669 107.505 53.5408 107.546 53.53C107.608 53.5138 107.654 53.4796 107.684 53.4275C107.72 53.3961 107.769 53.3722 107.831 53.356C107.893 53.3397 107.947 53.3365 107.994 53.3463C107.994 53.3463 108.02 53.3616 108.072 53.392C108.104 53.4279 108.107 53.4822 108.082 53.5549C108.072 53.6016 108.07 53.6352 108.075 53.6559C108.086 53.6971 108.102 53.7151 108.122 53.7097L108.13 53.7406L108.031 53.8659L108.047 53.9278C108.172 53.9833 108.264 54.1246 108.324 54.3515L108.389 54.5992C108.432 54.7643 108.45 55.0021 108.444 55.3126C108.461 55.4625 108.507 55.6819 108.583 55.9707L108.632 56.1565C108.697 56.4041 108.798 56.6642 108.936 56.9369C109.015 57.0705 109.118 57.297 109.246 57.6163C109.289 57.6935 109.31 57.776 109.311 57.864C109.333 57.9465 109.365 58.0263 109.407 58.1035C109.434 58.2066 109.495 58.356 109.591 58.5515C109.687 58.835 109.833 59.1826 110.03 59.5943L110.373 60.3975L110.636 61.0232C110.753 61.3013 110.833 61.5228 110.877 61.6879C111.004 62.0073 111.09 62.2495 111.133 62.4146C111.139 62.4352 111.152 62.4428 111.172 62.4374C111.205 62.5612 111.269 62.7209 111.364 62.9164L111.467 63.0549C111.524 63.106 111.609 63.2603 111.72 63.5177C111.731 63.559 111.747 63.6209 111.769 63.7034C111.806 63.7599 111.812 63.8245 111.787 63.8973L111.834 63.951L111.888 63.9038L111.945 63.4918L112.04 62.9707L112.137 62.5815L112.195 62.3014L112.323 61.9041L112.396 61.554L112.424 61.282C112.434 61.2353 112.456 61.1083 112.49 60.9009L112.606 60.2088C112.61 60.1415 112.617 60.0845 112.627 60.0378C112.632 59.9705 112.639 59.9135 112.649 59.8668L112.699 59.5557L112.822 58.7626L112.848 58.3587L112.965 57.6666L113.066 57.0445L113.166 56.2904L113.349 55.3492C113.364 55.2352 113.38 55.1315 113.4 55.0381C113.44 54.9393 113.463 54.8563 113.467 54.789C113.512 54.6229 113.558 54.3791 113.606 54.0578L113.722 53.3656L113.791 53.2484L113.784 53.3494L113.735 53.7924L113.72 53.8624C113.669 53.9199 113.645 54.0366 113.647 54.2125C113.652 54.2332 113.645 54.2902 113.625 54.3835C113.626 54.4715 113.607 54.6088 113.568 54.7956C113.548 54.8889 113.523 54.9617 113.493 55.0138C113.493 55.0138 113.496 55.0241 113.501 55.0447C113.501 55.0447 113.511 55.042 113.532 55.0366L113.563 55.0285L113.568 54.7956L113.6 54.9194L113.625 55.0122C113.61 55.0383 113.605 55.0616 113.61 55.0823C113.636 55.0975 113.667 55.0894 113.703 55.0579C113.739 55.0264 113.765 55.0417 113.781 55.1036C113.755 55.0884 113.734 55.0938 113.719 55.1198C113.704 55.1459 113.696 55.1589 113.696 55.1589L113.713 55.2208L113.752 55.2436C113.797 55.1655 113.807 55.1188 113.781 55.1036C113.853 55.0407 113.868 54.9706 113.825 54.8935C113.825 54.8935 113.812 54.8859 113.786 54.8707C113.775 54.8294 113.791 54.8034 113.832 54.7925C113.816 54.7306 113.828 54.6943 113.869 54.6834C113.89 54.678 113.895 54.6547 113.884 54.6134C113.832 54.583 113.837 54.5596 113.899 54.5434L113.891 54.5124C113.865 54.4972 113.852 54.4896 113.852 54.4896C113.867 54.4635 113.872 54.4402 113.866 54.4196L113.901 54.0466L113.945 53.8365C113.96 53.8105 113.983 53.7274 114.012 53.5874L114.027 53.5174L114.128 53.524L114.159 53.5158C114.174 53.4898 114.168 53.4692 114.142 53.4539L114.111 53.4621L114.027 53.5174L114.048 53.3464L114.102 53.2992L114.133 53.2911C114.164 53.3269 114.195 53.3188 114.226 53.2667L114.278 53.0876C114.267 53.0463 114.272 53.023 114.293 53.0176L114.307 52.9475L114.324 53.0094L114.289 53.3824L114.274 53.4524C114.244 53.5045 114.242 53.5382 114.268 53.5534C114.253 53.5794 114.25 53.6131 114.261 53.6544C114.287 53.6696 114.293 53.6902 114.277 53.7163L114.286 53.7472C114.286 53.7472 114.275 53.7499 114.255 53.7553C114.255 53.7553 114.252 53.745 114.246 53.7244L114.238 53.6934L114.23 53.6625L114.238 53.6934L114.209 53.8335C114.178 53.8856 114.197 53.9138 114.264 53.9182L114.28 53.9801C114.261 54.0735 114.259 54.1511 114.275 54.213C114.275 54.213 114.27 54.2364 114.261 54.2831C114.266 54.3037 114.289 54.3086 114.331 54.2978L114.355 54.3906C114.334 54.3961 114.327 54.4091 114.332 54.4297L114.394 54.4135L114.446 54.2344C114.487 54.1356 114.521 53.9722 114.549 53.7442L114.577 53.4722C114.572 53.4516 114.569 53.4413 114.569 53.4413C114.59 53.4358 114.6 53.4331 114.6 53.4331L114.608 53.4641C114.564 53.6302 114.55 53.7882 114.567 53.938L114.575 53.969C114.596 53.9636 114.603 53.9505 114.598 53.9299L114.641 53.5879C114.651 53.5412 114.678 53.4348 114.722 53.2687C114.717 53.2481 114.714 53.2378 114.714 53.2378C114.73 53.2117 114.724 53.1911 114.698 53.1759C114.693 53.1552 114.7 53.1422 114.721 53.1368C114.736 53.1108 114.738 53.0771 114.727 53.0358L114.767 53.0587C114.751 53.0847 114.746 53.108 114.752 53.1287C114.778 53.1439 114.783 53.1645 114.768 53.1906C114.753 53.2166 114.761 53.2916 114.794 53.4154L114.848 53.3682L114.884 53.1272C114.914 53.0751 114.95 53.0436 114.991 53.0328L115.045 52.9856L115.06 52.9156L115.037 52.9546L114.983 53.0018C114.972 52.9606 114.977 52.9372 114.998 52.9318C114.993 52.9112 115.005 52.8748 115.035 52.8227L115.066 52.8146L115.088 52.6436C115.108 52.6382 115.119 52.6355 115.119 52.6355C115.113 52.6148 115.111 52.6045 115.111 52.6045C115.193 52.5829 115.218 52.5101 115.186 52.3863C115.18 52.3657 115.188 52.3527 115.209 52.3472C115.244 52.3158 115.275 52.3077 115.301 52.3229C115.395 52.3425 115.459 52.3366 115.495 52.3051L115.557 52.2889C115.563 52.3095 115.555 52.3226 115.534 52.328L115.36 52.6715L115.294 53.0526C115.274 53.058 115.266 53.071 115.271 53.0916C115.292 53.0862 115.3 53.0732 115.294 53.0526C115.33 53.0211 115.358 52.9587 115.377 52.8653L115.43 52.6862C115.429 52.5983 115.482 52.5071 115.59 52.4127C115.625 52.3812 115.653 52.3188 115.673 52.2255L115.741 52.1083L115.803 52.092L115.828 52.1849L115.805 52.2239L115.836 52.2158C115.877 52.205 115.892 52.179 115.881 52.1377C115.855 52.1225 115.853 52.1121 115.873 52.1067C115.888 52.0807 115.906 52.065 115.927 52.0595C115.989 52.0433 116.027 51.9782 116.041 51.8642C116.041 51.8642 116.102 51.76 116.224 51.5516L116.232 51.5826L116.165 51.8317C116.161 51.899 116.177 51.9609 116.214 52.0174C116.266 52.0479 116.302 52.0604 116.323 52.055C116.385 52.0387 116.4 52.0567 116.37 52.1088L116.332 52.2179C116.211 52.4262 116.131 52.6678 116.092 52.9425C116.019 53.3366 115.988 53.7198 115.997 54.0923C115.983 54.2063 115.971 54.3306 115.963 54.4652C115.974 54.5945 115.973 54.7161 115.959 54.8301C115.947 55.12 115.912 55.449 115.854 55.817C115.851 55.9723 115.825 56.2106 115.777 56.532C115.772 56.5993 115.761 56.7236 115.742 56.9049C115.739 57.0602 115.712 57.2106 115.662 57.356L115.672 57.5189L115.596 58.3658L115.565 59.0026C115.543 59.3392 115.522 59.5542 115.502 59.6476C115.514 59.7768 115.498 59.9245 115.453 60.0906C115.43 60.3392 115.379 60.6063 115.299 60.8918C115.312 61.109 115.309 61.2642 115.289 61.3576L115.274 61.4276L115.232 61.7696L115.21 62.5693L115.179 63.2062C115.174 63.2735 115.167 63.3305 115.157 63.3772C115.142 63.4032 115.127 63.4292 115.112 63.4553C115.122 63.4966 115.12 63.5302 115.105 63.5563C115.11 63.5769 115.103 63.6339 115.084 63.7273C115.026 64.0953 114.972 64.3521 114.922 64.4975L114.878 64.7076C114.888 64.7489 114.884 64.7722 114.863 64.7776L114.724 65.5088C114.634 65.7531 114.608 65.9914 114.647 66.2238L114.596 66.5349L114.548 67.1098C114.513 67.2292 114.492 67.3562 114.483 67.4908C114.489 67.5994 114.483 67.7004 114.463 67.7938C114.438 67.8665 114.447 67.9854 114.49 68.1505C114.512 68.233 114.567 68.2738 114.655 68.2728C114.722 68.2772 114.761 68.3 114.772 68.3413C114.804 68.3772 114.814 68.4184 114.805 68.4651L114.785 68.768L114.819 69.0238C114.84 69.1063 114.823 69.166 114.766 69.2029L114.551 69.3917L114.498 69.4389C114.478 69.5322 114.419 69.6028 114.321 69.6505C114.244 69.6927 114.195 69.7166 114.175 69.722L113.983 69.8717C113.941 69.8825 113.882 69.9091 113.805 69.9514C113.733 70.0143 113.664 70.0435 113.596 70.0391L113.054 70.1152L112.844 70.0711C112.481 70.0339 112.217 69.993 112.051 69.9483C111.983 69.9439 111.924 69.9265 111.872 69.896C111.84 69.8602 111.801 69.8373 111.754 69.8275C111.567 69.7003 111.363 69.5112 111.142 69.2602C110.959 69.0657 110.751 68.7783 110.519 68.3981L110.085 67.7511L109.854 67.2493C109.78 67.1363 109.73 67.0282 109.703 66.925C109.618 66.7708 109.507 66.5134 109.368 66.1527C109.315 66.0343 109.248 65.8644 109.168 65.6428C109.088 65.4212 109.023 65.2176 108.975 65.0318C108.927 64.9341 108.892 64.8439 108.871 64.7614C108.864 64.6528 108.837 64.5496 108.79 64.4519L108.668 63.9876C108.572 63.792 108.511 63.6427 108.484 63.5395L108.211 62.751C108.168 62.5859 108.088 62.3643 107.971 62.0862C107.933 61.9418 107.855 61.7305 107.738 61.4525C107.722 61.3906 107.688 61.3444 107.636 61.3139L107.606 61.454C107.567 61.6407 107.548 61.7781 107.549 61.866C107.571 61.9486 107.574 62.0468 107.56 62.1608C107.54 62.2542 107.526 62.3242 107.516 62.3709L107.459 62.7829C107.429 62.923 107.4 63.063 107.37 63.2031C107.341 63.3431 107.319 63.4701 107.305 63.5842C107.252 63.9728 107.214 64.2035 107.189 64.2763C107.184 64.3436 107.157 64.45 107.107 64.5954C107.123 64.6574 107.124 64.7013 107.108 64.7274C107.119 64.7686 107.097 64.8957 107.043 65.1085C107.054 65.1497 107.032 65.2768 106.978 65.4895L106.817 66.3917L106.655 67.162L106.549 68.017L106.493 68.561C106.459 68.7683 106.437 68.8954 106.427 68.9421L106.4 69.214C106.375 69.2868 106.358 69.3904 106.349 69.5251C106.35 69.613 106.354 69.7113 106.36 69.8199C106.361 69.9079 106.352 69.9985 106.332 70.0919C106.321 70.4697 106.353 70.8031 106.429 71.092L106.551 71.5563L106.656 71.9587C106.726 72.139 106.881 72.352 107.122 72.5975C107.127 72.6182 107.14 72.6258 107.161 72.6204C107.187 72.6356 107.202 72.6535 107.208 72.6742C107.234 72.6894 107.252 72.7176 107.263 72.7589C107.222 72.7697 107.199 72.7648 107.193 72.7442C107.167 72.729 107.139 72.7474 107.108 72.7995C107.083 72.8722 107.032 72.8858 106.954 72.8401L106.766 72.7569ZM105.197 71.9445C105.176 71.9499 105.163 71.9423 105.158 71.9216L105.085 71.6431L105.132 71.6969L105.189 71.9135C105.215 71.9288 105.228 71.9364 105.228 71.9364C105.207 71.9418 105.197 71.9445 105.197 71.9445ZM105.321 71.912C105.3 71.9174 105.287 71.9098 105.282 71.8892L105.195 71.8126L105.202 71.7116L105.233 71.7035C105.264 71.7393 105.291 71.7985 105.313 71.8811L105.321 71.912ZM105.178 71.6187C105.146 71.5829 105.115 71.591 105.085 71.6431L105.083 71.5111C105.078 71.4905 105.085 71.4775 105.106 71.4721C105.112 71.4927 105.114 71.503 105.114 71.503L105.209 71.6106C105.214 71.6312 105.206 71.6443 105.186 71.6497L105.178 71.6187ZM104.634 70.9342L104.639 70.7013L104.631 70.6703L104.639 70.7013C104.666 70.8045 104.675 70.8794 104.665 70.9261L104.634 70.9342ZM105.274 71.2295C105.295 71.2241 105.302 71.2111 105.297 71.1904C105.312 71.1644 105.312 71.1204 105.295 71.0585L105.287 71.0276C105.267 71.033 105.259 71.046 105.264 71.0666C105.249 71.0927 105.25 71.1367 105.266 71.1986L105.274 71.2295ZM105.03 68.9116L104.952 68.8659L104.931 69.0369L104.961 69.0288L105.03 68.9116ZM103.969 67.7674C103.998 67.6273 104.021 67.5443 104.036 67.5182L104.028 67.4873L104.036 67.5182L104.008 67.7902C103.987 67.7956 103.98 67.8086 103.985 67.8293L103.969 67.7674ZM104.904 68.0515C104.959 67.9267 104.963 67.7714 104.914 67.5857L104.883 67.5938C104.873 67.6405 104.863 67.6872 104.853 67.7339C104.838 67.7599 104.839 67.8039 104.855 67.8658C104.877 67.9483 104.883 68.0129 104.873 68.0596L104.881 68.0906L104.904 68.0515ZM105.734 66.6759C105.754 66.6705 105.762 66.6575 105.757 66.6368L105.786 66.4968L105.778 66.4658L105.747 66.4739C105.752 66.4946 105.745 66.5516 105.726 66.6449L105.734 66.6759ZM106.123 64.7543L106.092 64.7624L106.04 64.9415L106.048 64.9725L106.079 64.9643L106.123 64.7543ZM105.193 64.2372C105.213 64.1438 105.22 64.0868 105.215 64.0662L105.207 64.0352L105.162 64.2453L105.193 64.2372ZM106.144 64.5833C106.165 64.5779 106.173 64.5648 106.167 64.5442L106.19 64.5051C106.238 64.1838 106.284 63.94 106.329 63.7739C106.324 63.7533 106.323 63.7093 106.328 63.642C106.332 63.5747 106.342 63.528 106.357 63.5019L106.413 62.958L106.486 62.6079L106.478 62.5769C106.458 62.5823 106.45 62.5953 106.455 62.616L106.388 62.8651L106.413 62.958C106.413 62.958 106.398 62.984 106.367 63.0361C106.28 63.5442 106.225 63.9226 106.202 64.1712L106.136 64.5523L106.144 64.5833ZM110.238 65.5606L110.183 65.4758L110.168 65.5459L110.224 65.6306L110.238 65.5606ZM110.117 64.4676L110.031 64.391C110.025 64.3703 110.012 64.3627 109.992 64.3681L110 64.3991L110.063 64.5148C110.084 64.5094 110.097 64.517 110.102 64.5376L110.117 64.4676ZM106.544 62.1958L106.557 61.9939L106.549 61.9629L106.505 62.173L106.513 62.204L106.544 62.1958ZM109.928 64.2524L109.943 64.1824L109.935 64.1515C109.935 64.1515 109.924 64.1542 109.904 64.1596C109.904 64.1596 109.907 64.1699 109.912 64.1905L109.889 64.2296C109.941 64.2601 109.967 64.2753 109.967 64.2753L109.928 64.2524ZM110.071 63.1564L110.046 63.0635L110.015 63.0717L109.985 63.0798L109.986 63.2117L110.017 63.2036L110.071 63.1564ZM109.366 62.6135L109.334 62.4896L109.294 62.4668L109.303 62.4978C109.287 62.5238 109.285 62.5575 109.296 62.5987L109.304 62.6297L109.335 62.6216L109.366 62.6135ZM108.632 61.5819L108.608 61.489L108.6 61.458L108.569 61.4662C108.585 61.5281 108.586 61.572 108.57 61.5981C108.576 61.6187 108.599 61.6236 108.64 61.6128L108.632 61.5819ZM109.273 61.2485L109.295 61.2094L109.287 61.1785L109.225 61.1947C109.225 61.1947 109.215 61.1974 109.194 61.2028C109.194 61.2028 109.197 61.2131 109.203 61.2338C109.229 61.249 109.247 61.2772 109.258 61.3185L109.273 61.2485ZM109.097 60.8314C109.092 60.8107 109.089 60.8004 109.089 60.8004C109.11 60.795 109.12 60.7923 109.12 60.7923L109.135 60.7223C109.114 60.7277 109.098 60.7098 109.087 60.6685L109.056 60.6766L109.104 60.7304C109.109 60.751 109.101 60.7641 109.081 60.7695L109.097 60.8314ZM113.6 61.6022L113.531 61.7194L113.571 61.7422L113.6 61.6022ZM107.334 57.39C107.329 57.3694 107.326 57.3591 107.326 57.3591C107.347 57.3536 107.357 57.3509 107.357 57.3509L107.302 57.2662L107.287 57.3362L107.334 57.39ZM113.416 61.1541C113.421 61.0868 113.451 61.0347 113.508 60.9978L113.469 60.975L113.438 60.9831L113.369 61.1003C113.369 61.1003 113.372 61.1106 113.377 61.1313C113.377 61.1313 113.367 61.134 113.346 61.1394L113.416 61.1541ZM113.594 61.0745C113.676 61.0528 113.697 61.0034 113.654 60.9263L113.646 60.8953L113.599 60.8415L113.584 60.9116C113.61 60.9268 113.608 60.9604 113.578 61.0125L113.563 61.0826L113.594 61.0745ZM113.532 60.462L113.493 60.4392L113.425 60.5564L113.503 60.602L113.532 60.462ZM113.504 59.9733C113.524 59.9679 113.532 59.9549 113.526 59.9343C113.609 59.9126 113.642 59.8708 113.626 59.8089C113.62 59.7883 113.607 59.7807 113.587 59.7861L113.564 59.8252C113.575 59.8664 113.557 59.8822 113.51 59.8724L113.495 59.9424L113.504 59.9733ZM113.861 59.3172L113.875 59.2472L113.859 59.1853L113.789 59.1706L113.797 59.2015C113.823 59.2168 113.829 59.2374 113.814 59.2635L113.799 59.3335L113.861 59.3172ZM113.701 58.962L113.729 58.6901L113.667 58.7063L113.676 58.7372C113.696 58.7318 113.712 58.7498 113.723 58.791C113.692 58.8431 113.68 58.8795 113.685 58.9001L113.71 58.993L113.701 58.962ZM113.879 58.8824C113.9 58.877 113.907 58.8639 113.902 58.8433L113.931 58.7033L113.923 58.6723L113.892 58.6804L113.832 58.8286L113.879 58.8824ZM113.876 58.6185C113.897 58.6131 113.922 58.5843 113.953 58.5323C113.953 58.5323 113.942 58.535 113.922 58.5404C113.916 58.5197 113.916 58.5197 113.922 58.5404C113.88 58.5512 113.865 58.5772 113.876 58.6185ZM113.998 58.4541L113.982 58.3922L113.928 58.4394L113.897 58.4475C113.903 58.4681 113.895 58.4812 113.874 58.4866L113.944 58.5013L113.998 58.4541ZM113.933 58.2065L113.941 58.2374C113.983 58.2266 114.001 58.2109 113.995 58.1902C113.99 58.1696 113.961 58.1441 113.909 58.1136L113.88 58.2537L113.933 58.2065ZM113.979 58.1283C113.974 58.1077 113.971 58.0974 113.971 58.0974C113.992 58.092 114.002 58.0893 114.002 58.0893L113.994 58.0583C113.994 58.0583 113.988 58.0377 113.977 57.9964L113.916 58.0126L113.963 58.0664L113.979 58.1283ZM113.837 57.967L113.836 57.835L113.828 57.8041L113.797 57.8122L113.798 57.9441L113.806 57.9751L113.837 57.967ZM114.023 57.9183C114.018 57.8976 114.012 57.877 114.007 57.8564C114.017 57.8097 114.037 57.7603 114.067 57.7082L113.981 57.6316L113.95 57.6397L113.974 57.7325L113.983 57.7635C113.967 57.7895 113.965 57.8232 113.976 57.8645C113.981 57.8851 113.976 57.9085 113.961 57.9345L113.969 57.9655L114.023 57.9183ZM114.058 57.5453C114.032 57.5301 114.026 57.5095 114.041 57.4834C114.077 57.4519 114.092 57.4259 114.087 57.4053L114.071 57.3434L114.017 57.3905L114.01 57.4915L113.965 57.5697L114.058 57.5453ZM114.122 57.0323C114.116 57.0117 114.124 56.9986 114.144 56.9932L114.083 57.0095C114.083 57.0095 114.072 57.0122 114.052 57.0176C114.052 57.0176 114.054 57.0279 114.06 57.0485L114.107 57.1023L114.122 57.0323ZM114.117 56.6365C114.147 56.5844 114.157 56.5377 114.146 56.4965L114.078 56.6137C114.083 56.6343 114.096 56.6419 114.117 56.6365ZM114.233 56.5731C114.274 56.5623 114.292 56.5465 114.287 56.5259C114.281 56.5053 114.268 56.4976 114.247 56.5031L114.194 56.5502C114.199 56.5709 114.202 56.5812 114.202 56.5812C114.222 56.5758 114.233 56.5731 114.233 56.5731ZM114.342 55.9819C114.332 55.9407 114.334 55.907 114.349 55.881L114.318 55.8891L114.311 55.9901L114.319 56.021L114.342 55.9819ZM114.346 54.9884C114.346 54.9884 114.362 54.9623 114.392 54.9102L114.427 54.5373L114.41 54.4754L114.402 54.4444C114.387 54.4705 114.359 54.4889 114.317 54.4997L114.295 54.5388C114.347 54.5693 114.373 54.5845 114.373 54.5845C114.378 54.6051 114.371 54.6181 114.35 54.6236C114.329 54.629 114.322 54.642 114.327 54.6626C114.354 54.7658 114.352 54.8434 114.322 54.8955L114.346 54.9884ZM114.064 54.037C114.109 53.9588 114.132 53.9198 114.132 53.9198L114.062 53.905C114.068 53.9257 114.055 53.962 114.025 54.0141L114.064 54.037ZM114.123 53.7569C114.117 53.7362 114.104 53.7286 114.084 53.734L114.069 53.8041L114.116 53.8578L114.123 53.7569ZM114.175 53.5778L114.105 53.563L114.082 53.6021C114.082 53.6021 114.085 53.6124 114.09 53.6331C114.09 53.6331 114.1 53.6304 114.121 53.6249L114.175 53.5778ZM114.825 52.7786L114.894 52.6613L114.895 52.7933L114.873 52.8323L114.825 52.7786ZM115.449 53.012C115.444 52.9913 115.456 52.955 115.487 52.9029L115.448 52.88C115.406 52.8909 115.391 52.9169 115.402 52.9582L115.449 53.012ZM114.894 52.6613C114.878 52.5994 114.852 52.5842 114.816 52.6157C114.81 52.595 114.823 52.5587 114.853 52.5066L114.884 52.4985C114.879 52.4778 114.897 52.4621 114.938 52.4513C114.949 52.4925 114.947 52.5262 114.931 52.5522C114.937 52.5729 114.924 52.6092 114.894 52.6613ZM114.88 52.1027L114.909 51.9626L114.948 51.9855L114.888 52.1336L114.88 52.1027ZM120.323 69.2012C120.271 69.1707 120.177 69.1511 120.043 69.1423C120.033 69.189 120.002 69.1971 119.95 69.1666C119.795 69.1633 119.696 69.123 119.654 69.0459L119.512 68.8845L119.418 68.7769L119.401 68.715C119.391 68.6738 119.372 68.6455 119.346 68.6303L119.315 68.6384C119.31 68.6178 119.276 68.5716 119.213 68.4999C119.207 68.4792 119.189 68.451 119.157 68.4151C119.152 68.3945 119.151 68.3505 119.156 68.2832C119.171 68.2572 119.144 68.198 119.076 68.1056C119.045 68.0698 119.014 68.0779 118.983 68.13L118.991 68.1609C118.971 68.1663 118.958 68.1587 118.952 68.1381C118.92 68.0143 118.885 67.9241 118.848 67.8676C118.843 67.847 118.814 67.8215 118.762 67.791L118.746 67.7291L118.785 67.7519L118.816 67.7438C118.8 67.6819 118.781 67.6537 118.76 67.6591C118.74 67.6645 118.727 67.6569 118.721 67.6362C118.705 67.5743 118.705 67.5304 118.72 67.5043C118.714 67.4837 118.706 67.4527 118.696 67.4115L118.687 67.3805L118.665 67.4196L118.681 67.4815L118.65 67.4896C118.624 67.4744 118.603 67.4358 118.586 67.3739C118.555 67.338 118.547 67.3071 118.562 67.281C118.557 67.2604 118.551 67.2398 118.546 67.2191L118.577 67.211C118.607 67.1589 118.62 67.1226 118.614 67.1019C118.609 67.0813 118.58 67.0557 118.528 67.0253C118.497 66.9894 118.47 66.9302 118.448 66.8477C118.427 66.7652 118.423 66.6669 118.437 66.5529C118.431 66.4443 118.422 66.3694 118.411 66.3281C118.421 66.2814 118.428 66.2244 118.433 66.1571C118.437 66.0898 118.452 66.0198 118.477 65.947C118.486 65.8124 118.487 65.7348 118.482 65.7141L118.474 65.6832C118.474 65.6832 118.463 65.6859 118.443 65.6913C118.443 65.6913 118.446 65.7016 118.451 65.7222L118.415 65.9633C118.395 66.0566 118.391 66.1239 118.402 66.1652L118.348 66.2124L118.332 66.1505C118.321 66.1092 118.325 66.0419 118.345 65.9485C118.329 65.8866 118.33 65.809 118.35 65.7156C118.349 65.6277 118.351 65.55 118.355 65.4827C118.359 65.4154 118.364 65.3481 118.368 65.2808L118.388 64.9778C118.409 64.9724 118.409 64.9724 118.388 64.9778C118.383 64.9572 118.38 64.9469 118.38 64.9469L118.364 64.885C118.353 64.8437 118.357 64.7764 118.377 64.683L118.369 64.6521L118.338 64.6602L118.323 64.7302L118.3 64.7693L118.292 64.7383C118.292 64.7383 118.282 64.741 118.261 64.7465C118.261 64.7465 118.258 64.7361 118.253 64.7155L118.261 64.7465L118.217 64.9565L118.194 64.9956L118.186 64.9646C118.164 64.8821 118.159 64.8175 118.168 64.7708C118.152 64.7089 118.152 64.6649 118.167 64.6389C118.177 64.5922 118.186 64.5455 118.196 64.4988L118.148 64.3131L118.117 64.3212C118.096 64.3266 118.088 64.3397 118.094 64.3603L118.04 64.4075C118.04 64.4075 118.03 64.4102 118.009 64.4156C118.004 64.395 118.011 64.382 118.032 64.3765C118.01 64.294 118.017 64.237 118.053 64.2055L118.045 64.1746C118.044 64.0866 118.051 63.9857 118.065 63.8717C118.079 63.7577 118.091 63.6773 118.101 63.6306C118.12 63.5373 118.125 63.4699 118.114 63.4287C118.129 63.4026 118.127 63.3923 118.106 63.3977C118.101 63.3771 118.095 63.3564 118.09 63.3358C118.048 63.3466 118.03 63.3624 118.036 63.383C118.036 63.383 118.021 63.409 117.99 63.4611L117.966 63.3683L117.995 63.2282L117.987 63.1973L117.956 63.2054C117.967 63.2467 117.957 63.2934 117.927 63.3455L117.935 63.3764C117.93 63.3558 117.916 63.3482 117.896 63.3536L117.894 63.2216L117.886 63.1907C117.866 63.1961 117.858 63.2091 117.863 63.2298C117.833 63.2819 117.826 63.3389 117.842 63.4008C117.821 63.4062 117.814 63.4192 117.819 63.4398L117.881 63.4236C117.881 63.4236 117.884 63.4339 117.889 63.4545C117.889 63.4545 117.9 63.4518 117.92 63.4464C117.9 63.4518 117.892 63.4649 117.897 63.4855C117.83 63.4811 117.807 63.5202 117.829 63.6027L117.687 64.0701L117.679 64.0391L117.707 63.7671C117.74 63.5598 117.764 63.3551 117.777 63.1531L117.849 62.6711L117.864 62.6011C117.823 62.6119 117.805 62.6276 117.81 62.6482L117.766 62.8583L117.751 62.9283C117.74 62.8871 117.745 62.8637 117.766 62.8583L117.874 62.1352C117.928 61.9225 117.984 61.5881 118.041 61.1321L118.136 60.6109C118.16 60.4503 118.192 60.2765 118.231 60.0898C118.265 59.8824 118.285 59.6675 118.293 59.4449C118.281 59.3156 118.285 59.2044 118.305 59.111C118.324 59.0176 118.336 58.9373 118.341 58.87C118.389 58.5486 118.415 58.3103 118.418 58.155L118.494 57.3081L118.564 56.6941C118.582 56.4248 118.585 56.2256 118.573 56.0964L118.625 55.9173C118.668 55.5752 118.69 55.2826 118.693 55.0394C118.692 54.9515 118.711 54.8141 118.75 54.6274L118.73 53.541L118.824 53.0199L118.844 52.7169L118.888 52.5068L118.934 52.4287C118.918 52.3668 118.914 52.2685 118.923 52.1339L119.036 51.8066C119.051 51.7806 119.053 51.7469 119.042 51.7056C119.073 51.6535 119.098 51.6248 119.119 51.6194C119.181 51.6031 119.248 51.5635 119.319 51.5006L119.311 51.4697C119.315 51.4024 119.304 51.3171 119.277 51.2139C119.261 51.152 119.299 51.0869 119.391 51.0186C119.433 51.0077 119.461 50.9893 119.476 50.9633C119.491 50.9372 119.506 50.9112 119.522 50.8851C119.516 50.8645 119.529 50.8281 119.559 50.776C119.554 50.7554 119.561 50.7424 119.582 50.737L119.558 50.6441L119.612 50.5969L119.589 50.636L119.636 50.6898C119.656 50.6843 119.667 50.6816 119.667 50.6816C119.661 50.661 119.659 50.6507 119.659 50.6507C119.7 50.6399 119.723 50.6448 119.729 50.6654L119.76 50.6573L119.791 50.6492L119.799 50.6801L119.746 50.8592L119.771 50.9521L119.786 50.8821C119.78 50.8614 119.824 50.817 119.916 50.7486C119.937 50.7432 119.978 50.7324 120.04 50.7161C120.117 50.6739 120.168 50.6164 120.193 50.5436L120.216 50.5046L120.263 50.5583C120.274 50.5996 120.292 50.6279 120.318 50.6431C120.349 50.591 120.364 50.5649 120.364 50.5649C120.379 50.5389 120.424 50.4168 120.499 50.1986C120.571 50.1357 120.612 50.0809 120.622 50.0342C120.622 50.0342 120.632 50.0315 120.653 50.0261C120.673 50.0206 120.686 50.0283 120.692 50.0489C120.729 50.1054 120.783 50.1022 120.855 50.0392C120.849 50.0186 120.857 50.0056 120.878 50.0002L120.863 50.0702C120.868 50.0908 120.863 50.1142 120.848 50.1402C120.833 50.1663 120.838 50.1869 120.864 50.2021C120.89 50.2174 120.934 50.2168 120.996 50.2006C121.079 50.179 121.099 50.1296 121.057 50.0524C121.046 50.0112 121.061 49.9851 121.102 49.9743C121.164 49.9581 121.21 49.9239 121.241 49.8718C121.277 49.8403 121.326 49.8165 121.387 49.8003C121.449 49.784 121.504 49.7808 121.55 49.7906C121.55 49.7906 121.576 49.8058 121.629 49.8363C121.66 49.8721 121.663 49.9264 121.638 49.9992C121.628 50.0458 121.626 50.0795 121.632 50.1001C121.642 50.1414 121.658 50.1593 121.679 50.1539L121.687 50.1849L121.587 50.3102L121.604 50.3721C121.728 50.4276 121.821 50.5688 121.88 50.7958L121.945 51.0434C121.988 51.2085 122.007 51.4463 122 51.7569C122.017 51.9067 122.064 52.1261 122.139 52.415L122.188 52.6007C122.253 52.8484 122.354 53.1085 122.492 53.3812C122.571 53.5148 122.675 53.7413 122.803 54.0606C122.845 54.1377 122.867 54.2203 122.868 54.3082C122.889 54.3908 122.921 54.4706 122.964 54.5477C122.991 54.6509 123.052 54.8003 123.147 54.9958C123.244 55.2793 123.39 55.6269 123.586 56.0386L123.929 56.8418L124.193 57.4675C124.31 57.7455 124.39 57.9671 124.433 58.1322C124.561 58.4515 124.646 58.6937 124.69 58.8588C124.695 58.8795 124.708 58.8871 124.729 58.8817C124.761 59.0055 124.825 59.1651 124.921 59.3607L125.023 59.4992C125.081 59.5503 125.165 59.7045 125.277 59.962C125.288 60.0032 125.304 60.0651 125.326 60.1477C125.362 60.2042 125.368 60.2688 125.343 60.3415L125.391 60.3953L125.444 60.3481L125.502 59.9361L125.597 59.415L125.693 59.0258L125.752 58.7457L125.879 58.3484L125.953 57.9982L125.981 57.7263C125.99 57.6796 126.012 57.5525 126.046 57.3452L126.162 56.6531C126.167 56.5857 126.174 56.5287 126.184 56.4821C126.188 56.4147 126.195 56.3577 126.205 56.311L126.256 56L126.379 55.2069L126.405 54.803L126.521 54.1109L126.623 53.4888L126.723 52.7347L126.906 51.7934C126.92 51.6794 126.937 51.5758 126.956 51.4824C126.997 51.3836 127.019 51.3006 127.023 51.2332C127.068 51.0671 127.114 50.8234 127.162 50.502L127.279 49.8099L127.347 49.6927L127.341 49.7937L127.291 50.2367L127.277 50.3067C127.226 50.3642 127.201 50.4809 127.203 50.6568C127.209 50.6774 127.201 50.7344 127.182 50.8278C127.183 50.9158 127.164 51.0531 127.124 51.2398C127.105 51.3332 127.08 51.4059 127.049 51.458C127.049 51.458 127.052 51.4684 127.057 51.489C127.057 51.489 127.068 51.4863 127.088 51.4809L127.119 51.4728L127.124 51.2398L127.157 51.3637L127.181 51.4565C127.166 51.4826 127.161 51.5059 127.167 51.5265C127.193 51.5418 127.224 51.5336 127.259 51.5022C127.295 51.4707 127.321 51.4859 127.338 51.5479C127.312 51.5326 127.291 51.538 127.276 51.5641C127.26 51.5901 127.253 51.6032 127.253 51.6032L127.269 51.6651L127.308 51.6879C127.354 51.6098 127.364 51.5631 127.338 51.5479C127.409 51.4849 127.424 51.4149 127.382 51.3378C127.382 51.3378 127.369 51.3302 127.343 51.3149C127.332 51.2737 127.347 51.2476 127.388 51.2368C127.372 51.1749 127.385 51.1385 127.426 51.1277C127.446 51.1223 127.451 51.0989 127.441 51.0577C127.388 51.0272 127.393 51.0039 127.455 50.9877L127.447 50.9567C127.421 50.9415 127.408 50.9339 127.408 50.9339C127.423 50.9078 127.428 50.8845 127.423 50.8638L127.457 50.4909L127.501 50.2808C127.517 50.2548 127.539 50.1717 127.568 50.0317L127.583 49.9616L127.684 49.9682L127.715 49.9601C127.73 49.9341 127.725 49.9134 127.699 49.8982L127.668 49.9063L127.583 49.9616L127.604 49.7906L127.658 49.7434L127.689 49.7353C127.721 49.7712 127.752 49.7631 127.782 49.711L127.834 49.5319C127.824 49.4906 127.828 49.4672 127.849 49.4618L127.864 49.3918L127.88 49.4537L127.845 49.8267L127.831 49.8967C127.8 49.9488 127.798 49.9824 127.824 49.9977C127.809 50.0237 127.807 50.0574 127.818 50.0986C127.844 50.1139 127.849 50.1345 127.834 50.1606L127.842 50.1915C127.842 50.1915 127.832 50.1942 127.811 50.1996C127.811 50.1996 127.808 50.1893 127.803 50.1687L127.795 50.1377L127.787 50.1068L127.795 50.1377L127.765 50.2778C127.735 50.3299 127.753 50.3581 127.821 50.3625L127.837 50.4244C127.817 50.5178 127.816 50.5954 127.832 50.6573C127.832 50.6573 127.827 50.6807 127.817 50.7273C127.822 50.748 127.846 50.7529 127.887 50.7421L127.911 50.8349C127.891 50.8403 127.883 50.8534 127.889 50.874L127.951 50.8578L128.003 50.6786C128.043 50.5799 128.077 50.4165 128.106 50.1885L128.134 49.9165C128.128 49.8958 128.126 49.8855 128.126 49.8855C128.146 49.8801 128.157 49.8774 128.157 49.8774L128.165 49.9084C128.12 50.0745 128.106 50.2324 128.124 50.3823L128.132 50.4133C128.152 50.4078 128.16 50.3948 128.155 50.3742L128.197 50.0322C128.207 49.9855 128.234 49.8791 128.279 49.713C128.273 49.6924 128.271 49.6821 128.271 49.6821C128.286 49.656 128.281 49.6354 128.254 49.6201C128.249 49.5995 128.257 49.5865 128.277 49.5811C128.293 49.555 128.295 49.5214 128.284 49.4801L128.323 49.5029C128.308 49.529 128.303 49.5523 128.308 49.573C128.334 49.5882 128.34 49.6088 128.325 49.6349C128.309 49.6609 128.318 49.7358 128.35 49.8597L128.404 49.8125L128.44 49.5714C128.471 49.5193 128.507 49.4879 128.548 49.4771L128.602 49.4299L128.616 49.3598L128.593 49.3989L128.54 49.4461C128.529 49.4048 128.534 49.3815 128.554 49.3761C128.549 49.3554 128.561 49.3191 128.592 49.267L128.623 49.2589L128.644 49.0879C128.665 49.0824 128.675 49.0797 128.675 49.0797C128.67 49.0591 128.667 49.0488 128.667 49.0488C128.75 49.0271 128.775 48.9544 128.742 48.8306C128.737 48.81 128.744 48.7969 128.765 48.7915C128.801 48.7601 128.832 48.7519 128.858 48.7672C128.951 48.7868 129.016 48.7809 129.052 48.7494L129.114 48.7332C129.119 48.7538 129.111 48.7668 129.091 48.7722L128.916 49.1158L128.851 49.4968C128.83 49.5023 128.822 49.5153 128.828 49.5359C128.849 49.5305 128.856 49.5175 128.851 49.4968C128.887 49.4654 128.914 49.403 128.934 49.3096L128.986 49.1305C128.985 49.0425 129.038 48.9514 129.146 48.857C129.182 48.8255 129.21 48.7631 129.229 48.6697L129.298 48.5525L129.36 48.5363L129.384 48.6291L129.361 48.6682L129.392 48.6601C129.433 48.6493 129.449 48.6232 129.438 48.582C129.412 48.5667 129.409 48.5564 129.43 48.551C129.445 48.525 129.463 48.5092 129.483 48.5038C129.545 48.4876 129.583 48.4225 129.598 48.3085C129.598 48.3085 129.659 48.2043 129.78 47.9959L129.788 48.0268L129.721 48.276C129.717 48.3433 129.733 48.4052 129.77 48.4617C129.822 48.4921 129.859 48.5047 129.879 48.4992C129.941 48.483 129.957 48.5009 129.926 48.553L129.889 48.6621C129.767 48.8705 129.687 49.112 129.649 49.3867C129.576 49.7808 129.544 50.1641 129.553 50.5366C129.539 50.6506 129.528 50.7749 129.519 50.9095C129.531 51.0387 129.53 51.1604 129.515 51.2744C129.503 51.5643 129.468 51.8932 129.41 52.2613C129.407 52.4166 129.381 52.6549 129.333 52.9763C129.329 53.0436 129.317 53.1679 129.299 53.3492C129.295 53.5045 129.269 53.6549 129.219 53.8003L129.228 53.9632L129.153 54.8101L129.121 55.4469C129.099 55.7835 129.078 55.9985 129.059 56.0919C129.071 56.2211 129.054 56.3687 129.01 56.5348C128.986 56.7835 128.935 57.0505 128.856 57.3361C128.869 57.5532 128.865 57.7085 128.846 57.8019L128.831 57.8719L128.788 58.2139L128.766 59.0136L128.735 59.6504C128.731 59.7177 128.723 59.7747 128.714 59.8214C128.698 59.8475 128.683 59.8735 128.668 59.8996C128.679 59.9408 128.677 59.9745 128.661 60.0005C128.667 60.0212 128.66 60.0782 128.64 60.1716C128.582 60.5396 128.528 60.7964 128.478 60.9418L128.434 61.1519C128.445 61.1932 128.44 61.2165 128.419 61.2219L128.28 61.9531C128.19 62.1974 128.164 62.4357 128.203 62.6681L128.152 62.9791L128.105 63.554C128.07 63.6735 128.048 63.8005 128.039 63.9351C128.046 64.0437 128.039 64.1447 128.019 64.2381C127.994 64.3108 128.004 64.4297 128.047 64.5948C128.069 64.6773 128.123 64.7181 128.211 64.7171C128.279 64.7215 128.318 64.7443 128.329 64.7856C128.36 64.8214 128.371 64.8627 128.361 64.9094L128.341 65.2123L128.375 65.4681C128.397 65.5506 128.379 65.6103 128.323 65.6472L128.108 65.8359L128.054 65.8831C128.034 65.9765 127.976 66.047 127.878 66.0947C127.801 66.137 127.752 66.1609 127.731 66.1663L127.539 66.316C127.498 66.3268 127.438 66.3533 127.361 66.3956C127.29 66.4585 127.22 66.4878 127.153 66.4834L126.61 66.5595L126.4 66.5154C126.038 66.4782 125.773 66.4372 125.607 66.3926C125.54 66.3882 125.48 66.3708 125.428 66.3403C125.397 66.3045 125.358 66.2816 125.311 66.2718C125.123 66.1446 124.919 65.9555 124.699 65.7045C124.516 65.51 124.308 65.2226 124.076 64.8424L123.641 64.1954L123.411 63.6936C123.337 63.5806 123.286 63.4725 123.259 63.3693C123.175 63.2151 123.063 62.9576 122.924 62.597C122.871 62.4786 122.805 62.3086 122.725 62.0871C122.644 61.8655 122.58 61.6618 122.531 61.4761C122.483 61.3784 122.449 61.2882 122.427 61.2057C122.421 61.0971 122.394 60.9939 122.346 60.8961L122.224 60.4318C122.129 60.2363 122.068 60.087 122.041 59.9838L121.768 59.1952C121.724 59.0302 121.644 58.8086 121.527 58.5305C121.489 58.3861 121.412 58.1748 121.295 57.8967C121.278 57.8348 121.244 57.7887 121.192 57.7582L121.163 57.8983C121.123 58.085 121.104 58.2223 121.105 58.3103C121.127 58.3928 121.131 58.4911 121.116 58.6051C121.097 58.6985 121.082 58.7685 121.072 58.8152L121.015 59.2272C120.986 59.3672 120.956 59.5073 120.927 59.6473C120.897 59.7874 120.875 59.9144 120.861 60.0284C120.809 60.4171 120.77 60.6478 120.745 60.7206C120.741 60.7879 120.713 60.8943 120.663 61.0397C120.68 61.1016 120.68 61.1456 120.665 61.1717C120.676 61.2129 120.654 61.3399 120.599 61.5527C120.61 61.594 120.588 61.721 120.534 61.9338L120.374 62.836L120.212 63.6063L120.105 64.4613L120.049 65.0052C120.016 65.2126 119.994 65.3396 119.984 65.3863L119.956 65.6583C119.931 65.731 119.914 65.8347 119.905 65.9694C119.906 66.0573 119.91 66.1556 119.916 66.2642C119.917 66.3521 119.908 66.4428 119.888 66.5362C119.877 66.914 119.91 67.2474 119.985 67.5363L120.107 68.0006L120.213 68.403C120.282 68.5833 120.437 68.7962 120.678 69.0418C120.683 69.0625 120.696 69.0701 120.717 69.0647C120.743 69.0799 120.759 69.0978 120.764 69.1184C120.79 69.1337 120.809 69.1619 120.82 69.2032C120.778 69.214 120.755 69.2091 120.75 69.1885C120.724 69.1732 120.695 69.1917 120.665 69.2438C120.64 69.3165 120.588 69.33 120.51 69.2844L120.323 69.2012ZM118.753 68.3888C118.733 68.3942 118.72 68.3866 118.714 68.3659L118.641 68.0873L118.688 68.1411L118.745 68.3578C118.771 68.373 118.784 68.3806 118.784 68.3806C118.764 68.3861 118.753 68.3888 118.753 68.3888ZM118.877 68.3563C118.857 68.3617 118.844 68.3541 118.838 68.3334L118.752 68.2568L118.758 68.1558L118.789 68.1477C118.821 68.1836 118.847 68.2428 118.869 68.3253L118.877 68.3563ZM118.734 68.063C118.703 68.0271 118.672 68.0353 118.641 68.0873L118.64 67.9554C118.634 67.9348 118.642 67.9218 118.663 67.9163C118.668 67.937 118.671 67.9473 118.671 67.9473L118.765 68.0549C118.77 68.0755 118.763 68.0885 118.742 68.0939L118.734 68.063ZM118.191 67.3785L118.196 67.1456L118.188 67.1146L118.196 67.1456C118.223 67.2487 118.231 67.3237 118.222 67.3704L118.191 67.3785ZM118.831 67.6738C118.851 67.6684 118.859 67.6554 118.853 67.6347C118.869 67.6087 118.868 67.5647 118.852 67.5028L118.844 67.4718C118.823 67.4773 118.815 67.4903 118.821 67.5109C118.806 67.537 118.806 67.5809 118.822 67.6428L118.831 67.6738ZM118.586 65.3559L118.508 65.3102L118.487 65.4812L118.518 65.4731L118.586 65.3559ZM117.525 64.2116C117.555 64.0716 117.577 63.9885 117.592 63.9625L117.584 63.9315L117.592 63.9625L117.564 64.2345C117.544 64.2399 117.536 64.2529 117.542 64.2735L117.525 64.2116ZM118.46 64.4958C118.516 64.371 118.519 64.2157 118.47 64.03L118.439 64.0381C118.429 64.0848 118.42 64.1315 118.41 64.1781C118.395 64.2042 118.395 64.2482 118.411 64.3101C118.433 64.3926 118.439 64.4572 118.429 64.5039L118.437 64.5349L118.46 64.4958ZM119.29 63.1202C119.311 63.1147 119.318 63.1017 119.313 63.0811L119.343 62.941L119.334 62.9101L119.303 62.9182C119.309 62.9388 119.302 62.9958 119.282 63.0892L119.29 63.1202ZM119.679 61.1985L119.648 61.2067L119.596 61.3858L119.604 61.4167L119.635 61.4086L119.679 61.1985ZM118.75 60.6815C118.769 60.5881 118.777 60.5311 118.771 60.5105L118.763 60.4795L118.719 60.6896L118.75 60.6815ZM119.701 61.0275C119.721 61.0221 119.729 61.0091 119.724 60.9885L119.746 60.9494C119.794 60.628 119.841 60.3843 119.885 60.2182C119.88 60.1976 119.88 60.1536 119.884 60.0863C119.888 60.0189 119.898 59.9723 119.913 59.9462L119.969 59.4023L120.043 59.0521L120.035 59.0212C120.014 59.0266 120.006 59.0396 120.012 59.0603L119.945 59.3094L119.969 59.4023C119.969 59.4023 119.954 59.4283 119.924 59.4804C119.836 59.9885 119.781 60.3669 119.758 60.6155L119.693 60.9966L119.701 61.0275ZM123.795 62.0049L123.739 61.9201L123.725 61.9901L123.78 62.0749L123.795 62.0049ZM123.673 60.9119L123.587 60.8352C123.582 60.8146 123.569 60.807 123.548 60.8124L123.556 60.8434L123.62 60.9591C123.64 60.9536 123.653 60.9613 123.659 60.9819L123.673 60.9119ZM120.1 58.6401L120.113 58.4381L120.105 58.4072L120.061 58.6173L120.069 58.6482L120.1 58.6401ZM123.485 60.6967L123.499 60.6267L123.491 60.5957C123.491 60.5957 123.481 60.5984 123.46 60.6039C123.46 60.6039 123.463 60.6142 123.468 60.6348L123.446 60.6739C123.498 60.7043 123.524 60.7195 123.524 60.7195L123.485 60.6967ZM123.627 59.6007L123.603 59.5078L123.572 59.5159L123.541 59.5241L123.542 59.656L123.573 59.6479L123.627 59.6007ZM122.922 59.0577L122.89 58.9339L122.851 58.9111L122.859 58.942C122.844 58.9681 122.842 59.0017 122.852 59.043L122.861 59.074L122.891 59.0658L122.922 59.0577ZM122.189 58.0261L122.164 57.9333L122.156 57.9023L122.125 57.9104C122.141 57.9723 122.142 58.0163 122.127 58.0424C122.132 58.063 122.156 58.0679 122.197 58.0571L122.189 58.0261ZM122.829 57.6928L122.852 57.6537L122.844 57.6227L122.782 57.639C122.782 57.639 122.772 57.6417 122.751 57.6471C122.751 57.6471 122.754 57.6574 122.759 57.678C122.785 57.6933 122.804 57.7215 122.814 57.7628L122.829 57.6928ZM122.653 57.2756C122.648 57.255 122.645 57.2447 122.645 57.2447C122.666 57.2393 122.676 57.2366 122.676 57.2366L122.691 57.1666C122.67 57.172 122.655 57.154 122.644 57.1128L122.613 57.1209L122.66 57.1747C122.665 57.1953 122.658 57.2083 122.637 57.2137L122.653 57.2756ZM127.156 58.0464L127.088 58.1637L127.127 58.1865L127.156 58.0464ZM120.891 53.8343C120.885 53.8136 120.883 53.8033 120.883 53.8033C120.903 53.7979 120.914 53.7952 120.914 53.7952L120.858 53.7105L120.844 53.7805L120.891 53.8343ZM126.973 57.5984C126.977 57.5311 127.008 57.479 127.064 57.4421L127.025 57.4193L126.994 57.4274L126.926 57.5446C126.926 57.5446 126.928 57.5549 126.934 57.5756C126.934 57.5756 126.923 57.5783 126.903 57.5837L126.973 57.5984ZM127.15 57.5187C127.233 57.4971 127.253 57.4477 127.211 57.3706L127.203 57.3396L127.155 57.2858L127.141 57.3558C127.167 57.3711 127.164 57.4047 127.134 57.4568L127.119 57.5268L127.15 57.5187ZM127.089 56.9063L127.05 56.8834L126.981 57.0006L127.059 57.0463L127.089 56.9063ZM127.06 56.4176C127.081 56.4122 127.088 56.3992 127.083 56.3785C127.165 56.3569 127.199 56.3151 127.182 56.2532C127.177 56.2326 127.164 56.225 127.143 56.2304L127.12 56.2694C127.131 56.3107 127.113 56.3264 127.067 56.3166L127.052 56.3867L127.06 56.4176ZM127.417 55.7615L127.432 55.6915L127.416 55.6296L127.346 55.6149L127.354 55.6458C127.38 55.661 127.385 55.6817 127.37 55.7077L127.355 55.7777L127.417 55.7615ZM127.258 55.4063L127.286 55.1343L127.224 55.1506L127.232 55.1815C127.253 55.1761 127.268 55.194 127.279 55.2353C127.249 55.2874 127.236 55.3238 127.242 55.3444L127.266 55.4373L127.258 55.4063ZM127.435 55.3266C127.456 55.3212 127.464 55.3082 127.458 55.2876L127.488 55.1475L127.48 55.1166L127.449 55.1247L127.388 55.2729L127.435 55.3266ZM127.432 55.0628C127.453 55.0574 127.479 55.0286 127.509 54.9765C127.509 54.9765 127.499 54.9792 127.478 54.9846C127.473 54.964 127.473 54.964 127.478 54.9846C127.437 54.9955 127.422 55.0215 127.432 55.0628ZM127.555 54.8984L127.538 54.8365L127.485 54.8837L127.454 54.8918C127.459 54.9124 127.452 54.9254 127.431 54.9309L127.501 54.9456L127.555 54.8984ZM127.49 54.6508L127.498 54.6817C127.539 54.6709 127.557 54.6552 127.552 54.6345C127.546 54.6139 127.518 54.5883 127.465 54.5579L127.436 54.6979L127.49 54.6508ZM127.535 54.5726C127.53 54.552 127.527 54.5417 127.527 54.5417C127.548 54.5362 127.558 54.5335 127.558 54.5335L127.55 54.5026C127.55 54.5026 127.545 54.482 127.534 54.4407L127.472 54.4569L127.519 54.5107L127.535 54.5726ZM127.394 54.4113L127.392 54.2793L127.384 54.2484L127.353 54.2565L127.355 54.3884L127.363 54.4194L127.394 54.4113ZM127.58 54.3625C127.574 54.3419 127.569 54.3213 127.563 54.3006C127.573 54.254 127.593 54.2046 127.624 54.1525L127.537 54.0758L127.507 54.084L127.531 54.1768L127.539 54.2078C127.524 54.2338 127.522 54.2675 127.532 54.3088C127.538 54.3294 127.533 54.3527 127.518 54.3788L127.526 54.4097L127.58 54.3625ZM127.614 53.9896C127.588 53.9744 127.583 53.9537 127.598 53.9277C127.634 53.8962 127.649 53.8702 127.644 53.8495L127.627 53.7876L127.573 53.8348L127.567 53.9358L127.521 54.0139L127.614 53.9896ZM127.678 53.4766C127.673 53.4559 127.68 53.4429 127.701 53.4375L127.639 53.4537C127.639 53.4537 127.629 53.4564 127.608 53.4619C127.608 53.4619 127.611 53.4722 127.616 53.4928L127.663 53.5466L127.678 53.4766ZM127.673 53.0808C127.704 53.0287 127.714 52.982 127.703 52.9407L127.634 53.0579C127.64 53.0786 127.653 53.0862 127.673 53.0808ZM127.789 53.0174C127.83 53.0065 127.848 52.9908 127.843 52.9702C127.838 52.9495 127.825 52.9419 127.804 52.9473L127.75 52.9945C127.755 53.0152 127.758 53.0255 127.758 53.0255C127.779 53.0201 127.789 53.0174 127.789 53.0174ZM127.899 52.4262C127.888 52.3849 127.89 52.3513 127.905 52.3252L127.874 52.3333L127.868 52.4343L127.876 52.4653L127.899 52.4262ZM127.903 51.4327C127.903 51.4327 127.918 51.4066 127.948 51.3545L127.983 50.9816L127.967 50.9197L127.959 50.8887C127.943 50.9148 127.915 50.9332 127.874 50.944L127.851 50.9831C127.903 51.0135 127.929 51.0288 127.929 51.0288C127.935 51.0494 127.927 51.0624 127.906 51.0678C127.886 51.0732 127.878 51.0863 127.884 51.1069C127.911 51.2101 127.909 51.2877 127.878 51.3398L127.903 51.4327ZM127.62 50.4812C127.666 50.4031 127.689 50.364 127.689 50.364L127.619 50.3493C127.624 50.3699 127.612 50.4063 127.581 50.4584L127.62 50.4812ZM127.679 50.2011C127.674 50.1805 127.661 50.1729 127.64 50.1783L127.625 50.2483L127.672 50.3021L127.679 50.2011ZM127.731 50.022L127.661 50.0073L127.638 50.0464C127.638 50.0464 127.641 50.0567 127.647 50.0773C127.647 50.0773 127.657 50.0746 127.678 50.0692L127.731 50.022ZM128.382 49.2228L128.45 49.1056L128.452 49.2375L128.429 49.2766L128.382 49.2228ZM129.005 49.4563C129 49.4356 129.013 49.3992 129.043 49.3472L129.004 49.3243C128.963 49.3351 128.947 49.3612 128.958 49.4025L129.005 49.4563ZM128.45 49.1056C128.434 49.0437 128.408 49.0285 128.372 49.0599C128.367 49.0393 128.379 49.0029 128.41 48.9509L128.441 48.9427C128.435 48.9221 128.453 48.9064 128.494 48.8955C128.505 48.9368 128.503 48.9705 128.488 48.9965C128.493 49.0172 128.481 49.0535 128.45 49.1056ZM128.436 48.5469L128.466 48.4069L128.505 48.4297L128.444 48.5779L128.436 48.5469ZM136.342 64.007C136.239 64.0341 136.135 64.0172 136.031 63.9563L135.899 63.9578C135.754 63.9957 135.617 63.9766 135.487 63.9005C135.399 63.9015 135.316 63.8791 135.238 63.8335C135.139 63.7932 135.028 63.7893 134.904 63.8218C134.889 63.8479 134.847 63.8587 134.78 63.8543C134.713 63.8499 134.658 63.8531 134.617 63.8639L134.166 63.7837C133.973 63.6359 133.773 63.5451 133.565 63.5113C133.425 63.4818 133.324 63.4752 133.262 63.4915C133.159 63.5185 133.071 63.4756 132.997 63.3626C132.939 63.3115 132.797 63.2717 132.569 63.2433C132.387 63.2247 132.156 63.098 131.874 62.8633C131.816 62.8122 131.656 62.6226 131.394 62.2944C131.32 62.1815 131.28 62.0707 131.273 61.9621L131.242 61.9702L131.246 61.6054C131.244 61.4294 131.235 61.3105 131.218 61.2486L131.215 60.9848C131.246 60.9327 131.261 60.8627 131.26 60.7747C131.259 60.6867 131.255 60.6325 131.25 60.6118C131.172 60.5661 131.138 60.52 131.147 60.4733C131.172 60.4006 131.182 60.3539 131.177 60.3332C131.16 60.1834 131.179 60.046 131.234 59.9212C131.253 59.7399 131.263 59.5276 131.266 59.2844C131.259 59.1758 131.281 59.0048 131.33 58.7714C131.349 58.678 131.405 58.3876 131.498 57.9001C131.506 57.6775 131.524 57.4962 131.554 57.3562C131.578 57.1955 131.597 57.0581 131.611 56.9441C131.671 56.752 131.713 56.5316 131.736 56.283C131.812 56.1527 131.828 56.0051 131.785 55.84L131.783 55.7081L131.819 55.467C131.84 55.4616 131.858 55.4459 131.873 55.4198C131.888 55.3938 131.893 55.3705 131.888 55.3498L131.925 55.2407C132.004 54.8673 132.043 54.6365 132.042 54.5486C132.086 54.3825 132.123 54.2294 132.153 54.0894C132.177 53.9287 132.198 53.8017 132.218 53.7083L132.336 53.1481C132.34 53.0808 132.352 52.9565 132.37 52.7751C132.389 52.5938 132.423 52.4304 132.473 52.285C132.528 52.0722 132.549 51.9012 132.537 51.772L132.593 51.228C132.633 51.1292 132.656 51.0462 132.66 50.9789C132.659 50.8909 132.663 50.8236 132.673 50.7769C132.657 50.715 132.664 50.614 132.693 50.474C132.729 50.4425 132.731 50.4089 132.7 50.373C132.683 50.3111 132.662 50.2725 132.636 50.2573L132.418 50.1822C132.413 50.1616 132.397 50.1436 132.371 50.1284C132.36 50.0871 132.362 50.0535 132.377 50.0274C132.35 49.9243 132.311 49.8574 132.259 49.827L132.242 49.7651L132.21 49.6413C132.131 49.5077 132.15 49.4143 132.269 49.3612C132.299 49.3091 132.361 49.2489 132.453 49.1805C132.674 49.0124 132.845 48.8242 132.967 48.6158C133.008 48.605 133.02 48.5686 133.004 48.5067L133.065 47.7298C133.075 47.6831 133.064 47.6419 133.033 47.606C133.022 47.5647 133.019 47.5104 133.023 47.4431C133.033 47.3964 133.045 47.3161 133.059 47.2021C133.088 47.062 133.139 46.9606 133.211 46.8976C133.317 46.7153 133.484 46.5944 133.711 46.5348C133.917 46.4807 134.075 46.4504 134.183 46.444C134.292 46.4376 134.411 46.4724 134.542 46.5485C134.609 46.5529 134.679 46.5676 134.752 46.5927C134.824 46.6177 134.894 46.6324 134.962 46.6368C134.993 46.6727 135.056 46.7004 135.149 46.72C135.263 46.7343 135.343 46.7463 135.39 46.7561L135.725 46.8997C135.778 46.9301 135.835 46.9372 135.896 46.921C136.087 46.805 136.233 46.6894 136.335 46.5744C136.714 46.2544 137.084 45.9811 137.443 45.7544C137.689 45.5136 137.945 45.314 138.212 45.1557C138.454 44.9821 138.657 44.8737 138.822 44.8304L139.038 44.7736L139.317 44.7005C139.338 44.6951 139.392 44.6919 139.48 44.6909C139.562 44.6692 139.632 44.6839 139.69 44.735C139.716 44.7502 139.75 44.7524 139.791 44.7416C139.832 44.7308 139.876 44.7303 139.923 44.7401C139.949 44.7553 139.983 44.7575 140.024 44.7467C140.045 44.7413 140.058 44.7489 140.063 44.7695L140.032 44.7776C140.011 44.7831 139.993 44.7988 139.978 44.8248C139.984 44.8455 139.986 44.8558 139.986 44.8558L140.034 44.9096L140.011 44.9486L140.066 45.0334L140.291 45.0075C140.291 45.0075 140.317 45.0227 140.369 45.0532C140.395 45.0684 140.424 45.0939 140.455 45.1298C140.481 45.145 140.513 45.1809 140.55 45.2374C140.566 45.2993 140.597 45.3351 140.644 45.3449C140.691 45.3548 140.727 45.3673 140.753 45.3825C140.774 45.3771 140.818 45.4206 140.887 45.5129C140.933 45.5227 140.97 45.5352 140.996 45.5505C141.042 45.5603 141.079 45.5728 141.105 45.588C141.209 45.6489 141.254 45.7363 141.24 45.8503C141.272 45.9742 141.286 46.0697 141.282 46.137L141.361 46.3146C141.404 46.3918 141.425 46.4743 141.426 46.5623L141.431 46.9581L141.395 47.1991L141.333 47.2153C141.281 47.1849 141.265 47.123 141.284 47.0296C141.3 47.0036 141.302 46.9699 141.291 46.9286C141.275 46.8667 141.254 46.8282 141.227 46.8129C141.196 46.7771 141.165 46.7412 141.133 46.7054C141.102 46.6695 141.045 46.6624 140.962 46.684C140.941 46.6895 140.937 46.7128 140.947 46.7541L140.933 46.8241L140.916 46.7622C140.89 46.747 140.869 46.7084 140.853 46.6465L140.667 46.6952L140.574 46.7196C140.507 46.7152 140.425 46.7368 140.327 46.7845C140.07 46.9841 139.875 47.1235 139.742 47.2026C139.521 47.3708 139.188 47.6126 138.741 47.9282C138.361 48.1603 138.089 48.342 137.925 48.4732C137.832 48.5415 137.694 48.644 137.509 48.7807C137.319 48.8967 137.154 48.984 137.015 49.0425C136.959 49.0794 136.895 49.1293 136.823 49.1922C136.767 49.2291 136.702 49.279 136.631 49.3419C136.518 49.4157 136.461 49.4525 136.461 49.4525C136.348 49.5263 136.25 49.574 136.168 49.5956C136.153 49.6217 136.117 49.6531 136.06 49.69C135.998 49.7063 135.97 49.7247 135.976 49.7453L135.954 49.9163L135.869 50.6003C135.849 50.6937 135.817 50.8234 135.773 50.9895C135.743 51.1296 135.724 51.2669 135.715 51.4016C135.666 51.635 135.637 51.819 135.629 51.9536C135.599 52.0937 135.559 52.2364 135.509 52.3819C135.48 52.522 135.453 52.6723 135.429 52.833L135.377 53.0121L135.385 53.0431L135.447 53.0268L135.778 52.7747C135.896 52.7215 136.01 52.6918 136.118 52.6853C136.165 52.6952 136.291 52.673 136.498 52.6189C136.56 52.6026 136.609 52.6228 136.646 52.6793C136.672 52.6945 136.706 52.6967 136.747 52.6859C136.949 52.699 137.07 52.7002 137.112 52.6894L137.128 52.7513L137.097 52.7594C137.076 52.7648 137.069 52.7779 137.074 52.7985C137.08 52.8191 137.072 52.8322 137.051 52.8376C137.072 52.8322 137.085 52.8398 137.09 52.8604C137.096 52.881 137.109 52.8887 137.129 52.8832L137.354 52.8574L137.385 52.8492L137.533 52.9096L137.426 53.004C137.343 53.0257 137.294 53.0495 137.279 53.0756L137.248 53.0837C137.254 53.1043 137.267 53.1119 137.287 53.1065L137.388 53.1131L137.698 53.0319C137.739 53.0211 137.806 53.0255 137.9 53.0451C137.968 53.1375 138.036 53.1858 138.103 53.1902L138.297 53.1725C138.364 53.1769 138.403 53.1997 138.414 53.241C138.42 53.2616 138.412 53.2746 138.391 53.2801L138.128 53.2831L138.066 53.2993C138.086 53.2939 138.099 53.3015 138.105 53.3222C138.142 53.3787 138.196 53.4194 138.269 53.4445C138.357 53.4434 138.424 53.4478 138.471 53.4577L138.815 53.6322C138.815 53.6322 138.817 53.6425 138.823 53.6632C138.823 53.6632 138.833 53.6605 138.854 53.655L138.761 53.6794C138.755 53.6588 138.742 53.6512 138.722 53.6566C138.701 53.662 138.691 53.6647 138.691 53.6647C138.649 53.5876 138.623 53.5723 138.613 53.619C138.597 53.6451 138.58 53.6608 138.559 53.6662L138.622 53.7819L138.81 53.8651C138.81 53.8651 138.812 53.8754 138.818 53.8961C138.844 53.9113 138.867 53.9162 138.888 53.9108C138.846 53.9216 138.8 53.9118 138.748 53.8814L138.717 53.8895C138.717 53.8895 138.696 53.8949 138.655 53.9057L138.71 53.9905C138.886 53.9884 139.013 54.0102 139.091 54.0559L139.303 54.232L139.381 54.2777C139.428 54.2875 139.436 54.3184 139.405 54.3705C139.39 54.3966 139.362 54.415 139.321 54.4258L139.11 54.3817L138.808 54.3619C138.714 54.3423 138.702 54.3786 138.77 54.471L138.778 54.5019L138.739 54.4791C138.708 54.4432 138.653 54.4465 138.576 54.4887L137.704 54.949L136.895 55.393L136.671 55.5508C136.383 55.7145 136.103 55.8652 135.83 56.0029C135.733 56.0506 135.638 56.1086 135.545 56.1769C135.448 56.2246 135.329 56.2777 135.19 56.3363C135.149 56.3471 135.082 56.3867 134.99 56.455C134.892 56.5027 134.791 56.5401 134.688 56.5671L134.612 56.6534C134.584 56.9694 134.55 57.1767 134.51 57.2755L134.427 57.4627C134.368 57.7428 134.31 58.0669 134.252 58.435C134.222 58.575 134.198 58.7357 134.18 58.917C134.176 59.0723 134.145 59.246 134.085 59.4382C134.03 60.0701 134.004 60.474 134.006 60.6499C134.007 60.7378 134.01 60.8361 134.017 60.9447C134.018 61.0327 134.035 61.1385 134.067 61.2623C134.068 61.3503 134.107 61.3731 134.184 61.3309C134.235 61.2733 134.282 61.2392 134.323 61.2284C134.379 61.1915 134.418 61.1703 134.439 61.1649L134.47 61.1568C134.449 61.1622 134.441 61.1752 134.447 61.1959L134.178 61.4318C134.157 61.4372 134.139 61.453 134.124 61.479C134.124 61.479 134.114 61.4817 134.093 61.4871L134.217 61.4547L134.456 61.3588L134.518 61.3425L134.495 61.3816L134.241 61.5475C134.185 61.5844 134.152 61.6262 134.142 61.6729C134.127 61.6989 134.137 61.7402 134.174 61.7967C134.18 61.8173 134.185 61.8379 134.19 61.8586C134.211 61.8532 134.224 61.8608 134.23 61.8814C134.24 61.9227 134.287 61.9325 134.37 61.9108L134.609 61.8149C134.666 61.7781 134.732 61.7385 134.81 61.6962C134.902 61.6279 135 61.5802 135.103 61.5531L135.165 61.5369C135.185 61.5315 135.206 61.526 135.227 61.5206C135.268 61.5098 135.302 61.512 135.328 61.5272C135.432 61.5881 135.509 61.5898 135.56 61.5323L136.439 60.9711L136.801 60.7108L136.863 60.6946C136.904 60.6837 136.96 60.6469 137.032 60.5839C137.104 60.521 137.178 60.4684 137.255 60.4261C137.291 60.3947 137.345 60.3475 137.417 60.2846C137.504 60.1956 137.596 60.1273 137.694 60.0796C137.714 60.0741 137.835 59.9874 138.056 59.8192C138.169 59.7455 138.251 59.6799 138.302 59.6224C138.373 59.5594 138.437 59.5096 138.494 59.4727C138.654 59.4087 138.731 59.3665 138.725 59.3458L138.74 59.2758C138.761 59.2704 138.774 59.278 138.779 59.2986C138.785 59.3193 138.787 59.3296 138.787 59.3296C138.833 59.2514 138.867 59.2536 138.888 59.3362C138.914 59.3514 138.938 59.3563 138.958 59.3509C138.999 59.3401 139.017 59.3243 139.012 59.3037L139.043 59.2956L139.105 59.2794L139.097 59.2484L139.081 59.1865C139.075 59.1659 139.083 59.1528 139.103 59.1474L139.111 59.1784L139.136 59.2712C139.136 59.2712 139.121 59.2973 139.09 59.3494L139.106 59.4113C139.112 59.4319 139.117 59.4526 139.123 59.4732C139.143 59.4678 139.156 59.4754 139.162 59.496C139.188 59.5112 139.26 59.5363 139.38 59.5711C139.401 59.5657 139.414 59.5733 139.419 59.594C139.545 59.7374 139.639 59.801 139.701 59.7847C139.721 59.7793 139.729 59.7663 139.723 59.7457C139.739 59.7196 139.757 59.7039 139.777 59.6985L139.8 59.6594C139.8 59.6594 139.803 59.6697 139.808 59.6904C139.829 59.685 139.849 59.6795 139.87 59.6741L139.878 59.7051L139.911 59.8289C139.931 59.8235 139.957 59.7947 139.987 59.7426C140.018 59.6905 140.03 59.6542 140.025 59.6335C140.025 59.6335 140.022 59.6232 140.017 59.6026C140.032 59.5765 140.037 59.5532 140.031 59.5326C140.052 59.5271 140.065 59.5348 140.071 59.5554C140.076 59.576 140.089 59.5836 140.11 59.5782L140.118 59.6092C140.087 59.6613 140.09 59.7156 140.127 59.7721C140.153 59.7873 140.175 59.8259 140.191 59.8878C140.259 59.9801 140.329 59.9948 140.401 59.9319C140.457 59.895 140.509 59.8815 140.556 59.8913C140.639 59.9576 140.666 60.0608 140.637 60.2008C140.57 60.2844 140.558 60.3647 140.601 60.4419C140.643 60.519 140.667 60.5679 140.672 60.5885L140.753 60.898L140.731 60.9371C140.731 60.9371 140.72 60.9398 140.7 60.9452C140.679 60.9506 140.666 60.943 140.661 60.9224C140.593 60.918 140.541 60.8876 140.504 60.8311C140.473 60.7952 140.45 60.7903 140.434 60.8163C140.384 60.9618 140.261 61.0822 140.066 61.1776C139.974 61.246 139.861 61.3197 139.727 61.3989C139.614 61.4726 139.493 61.5594 139.365 61.6592C139.252 61.7329 139.134 61.83 139.011 61.9504L138.981 61.9586C138.934 61.9487 138.895 61.9699 138.865 62.022C138.834 62.0741 138.809 62.1028 138.788 62.1082L138.765 62.1473L138.642 62.1798C138.637 62.2471 138.607 62.2992 138.55 62.3361C138.494 62.373 138.455 62.3941 138.435 62.3995L138.257 62.4792C138.144 62.5529 138.073 62.6598 138.043 62.7999L138.012 62.808C137.95 62.8242 137.873 62.8665 137.781 62.9348C137.689 63.0032 137.614 63.0558 137.558 63.0926L137.343 63.2814C137.322 63.2868 137.296 63.3156 137.266 63.3677C137.204 63.3839 137.173 63.392 137.173 63.392L137.111 63.4083C137.049 63.4245 136.982 63.4641 136.911 63.527C136.844 63.6106 136.783 63.6708 136.727 63.7076L136.627 63.833L136.435 63.9827L136.342 64.007ZM134.835 61.921L134.881 61.8428L134.819 61.8591C134.757 61.8753 134.721 61.9068 134.712 61.9535L134.689 61.9925L134.751 61.9763L134.835 61.921ZM132.423 60.0394L132.422 59.9075C132.416 59.8869 132.403 59.8793 132.382 59.8847L132.391 59.9156C132.375 59.9417 132.376 59.9857 132.392 60.0476L132.423 60.0394ZM135.081 61.7241C135.185 61.697 135.254 61.6678 135.29 61.6363L135.321 61.6282L135.282 61.6054L135.081 61.7241L135.051 61.7322C135.051 61.7322 135.053 61.7425 135.059 61.7632C135.079 61.7578 135.087 61.7447 135.081 61.7241ZM132.456 59.5346C132.487 59.4825 132.494 59.4255 132.477 59.3636L132.469 59.3326L132.438 59.3407L132.409 59.4808L132.425 59.5427L132.456 59.5346ZM137.611 61.6561C137.621 61.6094 137.636 61.5834 137.657 61.578C137.677 61.5726 137.695 61.5568 137.71 61.5308L138.01 61.2867C138.072 61.2705 138.139 61.2309 138.211 61.168L138.225 61.098L138.172 61.1452C137.976 61.2405 137.835 61.3327 137.748 61.4217C137.718 61.4738 137.666 61.5313 137.595 61.5942C137.574 61.5996 137.569 61.623 137.58 61.6642L137.611 61.6561ZM137.457 61.068C137.564 60.9736 137.675 60.8896 137.788 60.8158C137.901 60.7421 137.993 60.6738 138.065 60.6108L138.118 60.5636C138.077 60.5745 138.057 60.5799 138.057 60.5799L137.687 60.8092C137.651 60.8407 137.607 60.8852 137.556 60.9427C137.52 60.9741 137.477 61.0186 137.426 61.0761L137.395 61.0843L137.426 61.0761L137.457 61.068ZM138.379 60.2967C138.513 60.2176 138.613 60.1362 138.679 60.0527L138.803 60.0202L138.64 60.0298C138.538 60.1448 138.448 60.2235 138.371 60.2658C138.371 60.2658 138.374 60.2761 138.379 60.2967C138.379 60.2967 138.369 60.2994 138.348 60.3049L138.379 60.2967ZM140.975 47.1108L140.959 47.0489C140.942 46.987 140.942 46.943 140.957 46.917L140.988 46.9088L141.014 47.1336L140.983 47.1417L140.975 47.1108ZM157.567 52.2534C157.541 52.2381 157.523 52.2099 157.512 52.1686L157.465 52.1148L157.401 51.9991L157.393 51.9682L157.371 52.0073L157.341 52.1473C157.326 52.1734 157.308 52.1891 157.287 52.1945C157.282 52.1739 157.279 52.1635 157.279 52.1635C157.248 52.1277 157.214 52.1255 157.178 52.157C157.137 52.1678 157.116 52.1732 157.116 52.1732C157.101 52.1992 157.083 52.215 157.063 52.2204C157.036 52.2052 157.013 52.2003 156.992 52.2057C156.817 52.2077 156.708 52.2141 156.667 52.2249C156.558 52.2314 156.472 52.1987 156.409 52.127C156.242 51.9944 156.127 51.8922 156.064 51.8205C155.918 51.6825 155.826 51.5413 155.788 51.3968L155.786 51.2649L155.738 51.0792L155.696 50.7925L155.663 50.6687C155.633 50.7208 155.623 50.7674 155.634 50.8087C155.644 50.85 155.642 50.8836 155.627 50.9097L155.581 50.9878L155.526 50.9031C155.504 50.8206 155.498 50.712 155.507 50.5773L155.45 50.3607C155.475 50.2879 155.446 50.2624 155.364 50.284C155.281 50.3057 155.224 50.2546 155.191 50.1308L155.086 49.7284L155.077 49.6975L155.055 49.7365C155.055 49.7365 155.039 49.7626 155.009 49.8147L155.024 49.7446L155.043 49.4417L155.096 49.2626C155.136 49.1638 155.176 49.0211 155.215 48.8343C155.315 48.5434 155.38 48.3279 155.409 48.1879L155.445 47.9468L155.437 47.9159L155.375 47.9321C155.375 47.9321 155.337 47.9972 155.261 48.1275L155.23 48.1356L155.222 48.1046L155.206 48.0427L155.121 48.098L155.067 48.1452L155.051 48.0833L155.004 48.0295L154.95 48.0767C154.904 48.1549 154.882 48.1939 154.882 48.1939L154.851 48.2021L154.834 48.1402C154.891 48.1033 154.921 48.0512 154.926 47.9839C154.93 47.9166 154.937 47.8596 154.947 47.8129C154.947 47.8129 154.962 47.7868 154.993 47.7347C155.023 47.6826 155.038 47.6566 155.038 47.6566C155.054 47.6305 155.074 47.6251 155.1 47.6404C155.126 47.6556 155.147 47.6502 155.162 47.6241C155.234 47.5612 155.368 47.526 155.565 47.5186C155.668 47.4915 155.742 47.4389 155.788 47.3608C155.849 47.2566 155.868 47.1632 155.847 47.0807C155.831 47.0188 155.853 46.9357 155.914 46.8315C156.026 46.6698 156.097 46.5629 156.127 46.5108C156.244 46.2818 156.371 46.0941 156.509 45.9476C156.739 45.7328 156.936 45.5158 157.099 45.2966L157.473 44.7024C157.473 44.7024 157.526 44.6112 157.632 44.4289L157.981 43.7418L158.437 42.8284L158.837 41.8303L158.954 41.2701C158.969 41.2441 158.966 41.1898 158.945 41.1073L158.889 41.0225C158.868 40.94 158.887 40.8466 158.948 40.7424C159.004 40.6176 159.041 40.5085 159.061 40.4151C159.096 40.2957 159.126 40.1996 159.151 40.1269L159.142 40.096L159.112 40.1041L158.919 40.2538L158.243 40.8282L157.959 41.1342L157.667 41.4092C157.55 41.5502 157.481 41.6235 157.46 41.6289L157.1 42.0211L156.494 42.6102C156.401 42.6786 156.304 42.7703 156.202 42.8853C156.094 42.9797 155.969 43.0898 155.825 43.2156C155.708 43.3567 155.647 43.4609 155.643 43.5282L155.589 43.5754L155.242 43.7657L155.211 43.7738C155.144 43.7694 155.058 43.7807 154.955 43.8078C154.914 43.8186 154.826 43.8196 154.691 43.8108C154.665 43.7956 154.632 43.7934 154.59 43.8042C154.508 43.8259 154.417 43.8166 154.318 43.7763C154.22 43.736 154.157 43.7083 154.131 43.6931C154.012 43.6582 153.908 43.5973 153.819 43.5104C153.746 43.4854 153.678 43.437 153.615 43.3653C153.567 43.2675 153.528 43.2007 153.496 43.1649C153.444 43.1344 153.416 43.1089 153.41 43.0882C153.206 42.8991 152.972 42.7621 152.707 42.6772L152.606 42.6706C152.512 42.651 152.434 42.6053 152.371 42.5336L152.214 42.3103C152.182 42.2745 152.189 42.2175 152.235 42.1393L152.471 41.7796L152.809 41.4264L152.908 41.3011C152.984 41.1708 153.11 41.0607 153.285 40.9707L154.056 40.5039C154.112 40.467 154.253 40.3309 154.478 40.0954L154.8 39.8123L154.993 39.6626L155.746 39.0019C156.017 38.7763 156.256 38.5925 156.461 38.4504C156.687 38.3029 156.864 38.1792 156.993 38.0794C157.177 37.9428 157.318 37.8506 157.416 37.8029L157.716 37.5588L157.863 37.4873C157.981 37.4342 158.076 37.3762 158.148 37.3132C158.24 37.2449 158.315 37.1923 158.371 37.1554C158.443 37.0925 158.597 37.0079 158.834 36.9017C158.89 36.8648 158.981 36.8302 159.104 36.7977L159.344 36.7018C159.406 36.6856 159.525 36.6764 159.701 36.6744C159.721 36.669 159.755 36.6712 159.802 36.681C159.869 36.6854 159.918 36.7055 159.95 36.7414L160.137 36.8246C160.142 36.8452 160.158 36.8632 160.184 36.8784C160.205 36.873 160.215 36.8703 160.215 36.8703C160.251 36.8388 160.292 36.828 160.339 36.8378C160.38 36.827 160.419 36.8058 160.455 36.7744L160.486 36.7662C160.465 36.7717 160.455 36.7744 160.455 36.7744C160.449 36.7537 160.447 36.7434 160.447 36.7434L160.383 36.6277C160.409 36.6429 160.453 36.6424 160.515 36.6262C160.608 36.6458 160.681 36.6709 160.733 36.7013C160.873 36.7307 160.956 36.7531 160.982 36.7683C161.055 36.7933 161.12 36.8314 161.178 36.8824L161.365 36.9657C161.563 37.0462 161.713 37.1169 161.818 37.1778C161.838 37.1724 161.851 37.18 161.857 37.2006C161.904 37.2984 161.98 37.3777 162.085 37.4386C162.215 37.5147 162.28 37.5528 162.28 37.5528C162.373 37.5724 162.392 37.6006 162.335 37.6375C162.341 37.6581 162.336 37.6815 162.321 37.7075C162.321 37.7075 162.334 37.7151 162.36 37.7304L162.659 38.115C162.68 38.1096 162.682 38.1199 162.667 38.1459C162.667 38.1459 162.68 38.1536 162.706 38.1688C162.722 38.2307 162.744 38.2693 162.77 38.2845C162.863 38.3041 162.973 38.3856 163.098 38.5291C163.109 38.5703 163.107 38.604 163.092 38.63C163.056 38.6615 163.049 38.7185 163.07 38.801C163.087 38.8629 163.108 38.9015 163.134 38.9167C163.181 38.9265 163.189 38.9575 163.158 39.0096L163.144 39.0796L163.205 39.0634L163.275 39.0781L163.316 39.2329C163.244 39.2958 163.191 39.3869 163.156 39.5064C163.121 39.6258 163.091 39.7218 163.066 39.7946L162.472 41.4391C162.472 41.4391 162.343 41.7045 162.086 42.2353C161.925 42.6304 161.793 42.9294 161.692 43.1324L161.366 43.7804L160.927 44.7557L160.532 45.5209L159.878 46.6849C159.772 46.8672 159.555 47.1776 159.229 47.616L159.016 47.9367C159.016 47.9367 158.993 47.9758 158.947 48.0539L158.841 48.2802C158.791 48.4257 158.718 48.6102 158.622 48.8338C158.542 49.0314 158.449 49.2653 158.343 49.5356L158.083 50.5631C158.015 50.8899 157.997 51.1592 158.031 51.371C158.042 51.4122 158.021 51.4616 157.97 51.5191C157.95 51.5245 157.932 51.5403 157.917 51.5663C157.901 51.5924 157.896 51.6157 157.902 51.6363C157.863 51.8231 157.769 52.013 157.621 52.2062C157.58 52.217 157.562 52.2327 157.567 52.2534ZM157.13 57.3966C157.084 57.4748 156.971 57.5045 156.789 57.4859L156.641 57.4255C156.589 57.3951 156.545 57.3956 156.509 57.4271C156.474 57.4585 156.401 57.4335 156.291 57.352C156.249 57.2748 156.166 57.2525 156.042 57.285C155.98 57.3012 155.907 57.2762 155.824 57.2099L155.472 57.0044C155.347 56.9489 155.217 56.8288 155.08 56.6441L155.064 56.5822C155.074 56.5355 155.055 56.5073 155.008 56.4975C154.977 56.4616 154.943 56.4594 154.907 56.4909C154.892 56.5169 154.851 56.5277 154.784 56.5233L154.753 56.5315L154.598 56.5721C154.515 56.5937 154.462 56.6409 154.437 56.7136C154.442 56.7343 154.434 56.7473 154.414 56.7527L154.406 56.7217L154.389 56.6598C154.389 56.6598 154.379 56.6625 154.358 56.668C154.358 56.668 154.361 56.6783 154.367 56.6989L154.298 56.8161C154.257 56.8269 154.229 56.8454 154.213 56.8714L154.197 56.8095L154.212 56.7395C154.242 56.6874 154.239 56.6331 154.202 56.5766C154.186 56.5147 154.175 56.4734 154.17 56.4528C154.149 56.4582 154.133 56.4403 154.122 56.399C154.177 56.1862 154.199 56.0592 154.188 56.0179C154.272 55.6651 154.344 55.4366 154.405 55.3324C154.466 55.2282 154.514 55.1604 154.55 55.1289C154.642 54.9726 154.825 54.748 155.101 54.4551L155.285 54.2744L155.554 54.0385C155.59 54.007 155.639 53.9832 155.701 53.9669C155.784 53.9453 155.825 53.9784 155.826 54.0664C155.837 54.1077 155.856 54.1359 155.882 54.1511C155.908 54.1664 155.939 54.1582 155.975 54.1268C155.99 54.1007 156.018 54.0823 156.059 54.0715C156.095 54.04 156.154 54.0134 156.237 53.9918C156.361 53.9593 156.472 53.9632 156.571 54.0035C156.731 54.0275 156.838 54.0987 156.891 54.2171C156.944 54.2475 156.952 54.2785 156.916 54.31C156.916 54.31 156.921 54.3306 156.932 54.3719C156.938 54.3925 156.953 54.4104 156.979 54.4257L157.354 54.5921L157.432 54.6378C157.543 54.8072 157.596 54.9696 157.593 55.1249C157.578 55.1509 157.575 55.1846 157.586 55.2259L157.667 55.5354C157.684 55.5973 157.705 55.6359 157.731 55.6511C157.83 55.6913 157.875 55.7788 157.866 55.9134C157.861 55.9807 157.813 56.0486 157.721 56.1169C157.664 56.1538 157.644 56.2032 157.66 56.2651C157.666 56.2857 157.669 56.34 157.67 56.428C157.665 56.4953 157.648 56.555 157.618 56.6071L157.634 56.669C157.66 56.6842 157.665 56.7048 157.65 56.7309C157.522 56.8307 157.461 56.9349 157.467 57.0435C157.468 57.1314 157.43 57.1965 157.353 57.2388L157.13 57.3966ZM156.45 54.2998C156.45 54.2998 156.471 54.2944 156.512 54.2836L156.605 54.2592L156.613 54.2902L156.72 54.1958L156.603 54.1273C156.598 54.1066 156.575 54.1017 156.533 54.1126C156.518 54.1386 156.497 54.144 156.471 54.1288C156.445 54.1136 156.422 54.1087 156.401 54.1141L155.991 54.1887C155.97 54.1941 155.952 54.2098 155.937 54.2359C155.942 54.2565 155.945 54.2668 155.945 54.2668L155.961 54.3287C156.096 54.3375 156.184 54.3365 156.225 54.3257C156.251 54.3409 156.285 54.3431 156.326 54.3323C156.383 54.2954 156.424 54.2846 156.45 54.2998ZM154.529 50.6352L154.521 50.6042L154.474 50.5504L154.536 50.5342C154.557 50.5288 154.575 50.5131 154.59 50.487C154.626 50.4555 154.638 50.4192 154.627 50.3779C154.595 50.2541 154.575 50.1379 154.569 50.0293L154.489 49.8517L154.481 49.8208C154.502 49.8153 154.515 49.823 154.52 49.8436C154.578 49.8947 154.626 49.9924 154.663 50.1369L154.675 50.4317C154.644 50.4838 154.632 50.5202 154.637 50.5408L154.622 50.6108L154.653 50.6027L154.639 50.6727L154.529 50.6352ZM154.837 50.4221L154.805 50.2982L154.774 50.3064L154.872 50.0491C154.867 50.0285 154.874 50.0154 154.895 50.01C154.895 50.01 154.898 50.0203 154.903 50.041C154.903 50.041 154.893 50.0437 154.872 50.0491L154.883 50.3439L154.868 50.4139L154.854 50.484L154.837 50.4221ZM156.427 50.9315C156.421 50.9109 156.429 50.8979 156.45 50.8924L156.517 50.6433C156.496 50.6487 156.48 50.6308 156.469 50.5895L156.424 50.6677C156.424 50.6677 156.408 50.6937 156.378 50.7458L156.394 50.8077C156.394 50.8077 156.4 50.8283 156.41 50.8696L156.427 50.9315ZM158.056 46.7991L158.147 46.6428C158.177 46.5907 158.19 46.5543 158.184 46.5337C158.143 46.5445 158.115 46.5629 158.1 46.589L157.963 46.8234L157.948 46.8934L158.056 46.7991ZM158.483 46.1577L158.589 45.9314C158.589 45.9314 158.612 45.8923 158.657 45.8141L158.558 45.9395L158.444 46.1348C158.423 46.1402 158.416 46.1533 158.421 46.1739C158.442 46.1685 158.444 46.1788 158.429 46.2049L158.483 46.1577ZM158.781 45.7817C158.776 45.761 158.773 45.7507 158.773 45.7507C158.794 45.7453 158.804 45.7426 158.804 45.7426C158.865 45.6384 158.936 45.4875 159.016 45.29C159.037 45.2846 159.047 45.2819 159.047 45.2819C159.042 45.2612 159.039 45.2509 159.039 45.2509L159.008 45.259L158.931 45.3453C158.901 45.3974 158.876 45.4701 158.856 45.5635C158.831 45.6362 158.801 45.6883 158.765 45.7198L158.781 45.7817Z\" fill=\"#2D2C78\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-511c6df elementor-widget elementor-widget-spacer\" data-id=\"511c6df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Lange tijd waren de behandelingen voor artrose vooral gericht op het verlichten van de symptomen. Vandaag evolueert het onderzoek en richt het zich steeds meer op de biologische mechanismen van de aandoening. Een belangrijke evolutie voor de pati\u00ebnten!<\/p>\n","protected":false},"author":2,"featured_media":4543,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"footnotes":""},"categories":[51,57,50,53,58,62,70,55,73,56],"tags":[],"class_list":["post-4544","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evenwichtsparcours","category-masteropleiding","category-ontdekkingsroute","category-prestaties-traject","category-traject-herstart","category-evenwicht-verzorgen","category-master-verzorgen","category-prestatie-verzorgen","category-herstel-verzorgen","category-ontdekken-verzorgen"],"_links":{"self":[{"href":"https:\/\/arthroseactive.be\/nl\/wp-json\/wp\/v2\/posts\/4544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arthroseactive.be\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arthroseactive.be\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arthroseactive.be\/nl\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/arthroseactive.be\/nl\/wp-json\/wp\/v2\/comments?post=4544"}],"version-history":[{"count":14,"href":"https:\/\/arthroseactive.be\/nl\/wp-json\/wp\/v2\/posts\/4544\/revisions"}],"predecessor-version":[{"id":5492,"href":"https:\/\/arthroseactive.be\/nl\/wp-json\/wp\/v2\/posts\/4544\/revisions\/5492"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arthroseactive.be\/nl\/wp-json\/wp\/v2\/media\/4543"}],"wp:attachment":[{"href":"https:\/\/arthroseactive.be\/nl\/wp-json\/wp\/v2\/media?parent=4544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arthroseactive.be\/nl\/wp-json\/wp\/v2\/categories?post=4544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arthroseactive.be\/nl\/wp-json\/wp\/v2\/tags?post=4544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}